{"id":8951,"date":"2023-09-08T17:46:56","date_gmt":"2023-09-08T17:46:56","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2227722-09-04\/"},"modified":"2023-09-08T17:46:56","modified_gmt":"2023-09-08T17:46:56","slug":"2227722-09-04","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2227722-09-04\/","title":{"rendered":"22277(22-09-04)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 22277 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACION PENAL \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>Dr. \u00a0 MAURO \u00a0 SOLARTE \u00a0PORTILLA \u00a0\u00a0<\/p>\n<p>Aprobado acta No. 079 \u00a0<\/p>\n<p>Bogot\u00e1, D. C., veintid\u00f3s de septiembre del \u00a0a\u00f1o dos mil cuatro. \u00a0\u00a0<\/p>\n<p>Se pronuncia la Corte sobre la admisibilidad \u00a0de \u00a0la \u00a0demanda \u00a0de casaci\u00f3n discrecional que presenta e invoca el defensor del \u00a0procesado \u00a0LUIS \u00a0ATAULFO T\u00c9LLEZ JIM\u00c9NEZ, \u00a0contra \u00a0la \u00a0sentencia \u00a0de segunda instancia proferida el tres de \u00a0diciembre \u00a0de \u00a0dos mil tres por el Juzgado Segundo Penal del Circuito de Soacha, \u00a0Cundinamarca, \u00a0mediante \u00a0la cual lo conden\u00f3 a las penas principales de cuarenta \u00a0y \u00a0dos \u00a0(42) \u00a0meses \u00a0de \u00a0prisi\u00f3n, multa en cuant\u00eda de quince mil ( $15.000.00) \u00a0pesos \u00a0y la accesoria de inhabilitaci\u00f3n en el ejercicio de derechos y funciones \u00a0p\u00fablicas \u00a0por \u00a0t\u00e9rmino \u00a0igual \u00a0al \u00a0de\u00a0 \u00a0la \u00a0privaci\u00f3n \u00a0de la libertad, a \u00a0consecuencia \u00a0 de \u00a0 hallarlo \u00a0penalmente \u00a0responsable \u00a0del \u00a0delito \u00a0de \u00a0lesiones \u00a0personales imputado en el pliego enjuiciatorio. \u00a0\u00a0<\/p>\n<p>Asimismo, \u00a0conden\u00f3 \u00a0al \u00a0procesado\u00a0 \u00a0a \u00a0pagar \u00a0a \u00a0favor \u00a0del ofendido Jos\u00e9 Jairo Salguero Molano, la suma equivalente a \u00a0veinticinco \u00a0(25) \u00a0salarios \u00a0m\u00ednimos \u00a0legales \u00a0mensuales \u00a0por \u00a0concepto \u00a0de los \u00a0perjuicios \u00a0morales ocasionados con la infracci\u00f3n, y el equivalente a dieciocho \u00a0(18) \u00a0 salarios \u00a0 m\u00ednimos \u00a0legales \u00a0mensuales \u00a0vigentes \u00a0por \u00a0concepto \u00a0de \u00a0los \u00a0materiales.\u00a0 \u00a0\u00a0<\/p>\n<p>La \u00a0demanda.- \u00a0\u00a0<\/p>\n<p>Luego \u00a0de sintetizar los hechos, identificar \u00a0la \u00a0sentencia \u00a0materia de impugnaci\u00f3n y los sujetos procesales, y de resumir la \u00a0actuaci\u00f3n \u00a0llevada \u00a0a cabo en las instancias ordinarias del tr\u00e1mite, con apoyo \u00a0en \u00a0la \u00a0causal \u00a0primera \u00a0de \u00a0casaci\u00f3n, \u00a0dos \u00a0cargos \u00a0formula contra el fallo de \u00a0segunda \u00a0instancia, \u00a0en \u00a0los \u00a0que lo acusa de ser violatorio, por v\u00eda directa e \u00a0indirecta, respectivamente, de disposiciones de derecho sustancial. \u00a0\u00a0<\/p>\n<p>En \u00a0 el \u00a0primer \u00a0cargo, \u00a0sostiene que al ser condenado el procesado al \u00a0pago \u00a0de \u00a0los \u00a0perjuicios \u00a0morales \u00a0y \u00a0materiales \u00a0en \u00a0cuant\u00edas \u00a0equivalentes a \u00a0veinticinco \u00a0y \u00a0dieciocho \u00a0salarios m\u00ednimos legales mensuales, respectivamente, \u00a0\u201cse \u00a0viol\u00f3 \u00a0el \u00a0contenido \u00a0y alcance de lo dispuesto en el art\u00edculo 97 de la \u00a0Ley \u00a0 599 \u00a0 de \u00a02000 \u00a0por \u00a0interpretaci\u00f3n \u00a0err\u00f3nea, \u00a0en \u00a0raz\u00f3n \u00a0a \u00a0que \u00a0dicha \u00a0disposici\u00f3n \u00a0en \u00a0forma \u00a0clara \u00a0precept\u00faa \u00a0en \u00a0su \u00a0inciso \u00a0final que los da\u00f1os \u00a0materiales deben probarse en el proceso\u201d. \u00a0\u00a0<\/p>\n<p>En \u00a0este caso, dice, dentro de la actuaci\u00f3n \u00a0no \u00a0existe \u00a0ning\u00fan \u00a0medio \u00a0probatorio \u00a0que \u00a0indique \u00a0o \u00a0se\u00f1ale \u00a0los perjuicios \u00a0materiales \u00a0ocasionados \u00a0con la conducta punible, lo que permite concluir que el \u00a0sentenciador \u00a0vulner\u00f3 \u00a0la \u00a0disposici\u00f3n \u00a0en \u00a0comento \u00a0en la forma y sentido que \u00a0anota. \u00a0\u00a0<\/p>\n<p>En \u00a0el \u00a0segundo \u00a0cargo, \u00a0manifiesta \u00a0que \u00a0la \u00a0sentencia \u00a0es \u00a0violatoria, \u00a0por \u00a0d\u00eda indirecta, de los art\u00edculos 334 y 331 del \u00a0C\u00f3digo \u00a0Penal \u00a0de \u00a01980, \u00a0y \u00a0111 y 113 de la Ley 599 de 2000, a consecuencia de \u00a0incurrir \u00a0en \u00a0errores \u00a0de \u00a0hecho \u00a0en \u00a0la \u00a0apreciaci\u00f3n \u00a0probatoria, toda vez que \u00a0cercen\u00f3 \u00a0la \u00a0prueba documental que contiene la historia cl\u00ednica del lesionado, \u00a0seg\u00fan \u00a0la \u00a0cual el paciente ingres\u00f3 al establecimiento de salud por haber sido \u00a0atropellado \u00a0por \u00a0veh\u00edculo \u00a0automotor, \u00a0y \u00a0los testimonios de Arsenio de Jes\u00fas \u00a0Peralta \u00a0Valbuena, \u00a0Oscar Dar\u00edo Castro P\u00e9rez y Nydia Consuelo Gamboa Beltr\u00e1n, \u00a0quienes \u00a0afirman \u00a0que \u00a0el \u00a0procesado no intervino en la reyerta presentada y que \u00a0jam\u00e1s le vieron que portara elemento contundente alguno. \u00a0\u00a0<\/p>\n<p>Agrega \u00a0que Manuel Antonio Salguero, hermano \u00a0del \u00a0lesionado, \u00a0no \u00a0s\u00f3lo \u00a0incurri\u00f3 en serias contradicciones sino que afirm\u00f3 \u00a0que \u00a0para \u00a0el \u00a0momento de los hechos se hallaba en el hospital lo que indica que \u00a0no fue testigo presencial como en un comienzo lo hizo creer. \u00a0\u00a0<\/p>\n<p>Anota \u00a0que \u00a0los \u00a0juzgadores \u00a0desconocieron \u00a0la\u00a0 \u00a0presunci\u00f3n \u00a0de inocencia y la prevalencia del derecho sustancial pues \u00a0no \u00a0aparece \u00a0probado \u00a0que \u00a0su asistido fue la persona que ocasion\u00f3 las lesiones \u00a0pues \u00a0\u00e9stas \u00a0fueron \u00a0consecuencia \u00a0de \u00a0haber \u00a0sido \u00a0atropellado \u00a0por \u00a0veh\u00edculo \u00a0automotor. \u00a0\u00a0<\/p>\n<p>Con fundamento en lo expuesto, solicita de la \u00a0Corte \u00a0 \u00a0casar \u00a0 \u00a0el \u00a0 \u00a0fallo \u00a0 \u00a0atacado \u00a0 \u00a0(fls. \u00a0 \u00a020 \u00a0 \u00a0y \u00a0 ss. \u00a0 cno. \u00a0 sda. \u00a0inst.).\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0SE CONSIDERA: \u00a0\u00a0<\/p>\n<p>Como \u00a0quiera \u00a0que \u00a0la \u00a0sentencia \u00a0de segunda \u00a0instancia \u00a0fue \u00a0proferida por un juzgado penal del circuito, es claro que contra \u00a0ella \u00a0no \u00a0procede \u00a0la \u00a0casaci\u00f3n \u00a0com\u00fan \u00a0sino la discrecional que el demandante \u00a0invoca, \u00a0de manera que al haber ejercitado este derecho dentro de la oportunidad \u00a0prevista \u00a0por \u00a0el \u00a0ordenamiento, \u00a0se colige que tales aspectos pueden entenderse \u00a0cumplidos. \u00a0\u00a0<\/p>\n<p>No \u00a0acontece \u00a0igual, \u00a0sin \u00a0embargo, \u00a0en \u00a0lo \u00a0referente \u00a0a \u00a0la obligaci\u00f3n de fundamentar la solicitud frente al motivo que se \u00a0invoca \u00a0en \u00a0orden a demandar la admisi\u00f3n del tr\u00e1mite excepcional por la Corte, \u00a0y de acreditar el inter\u00e9s para acudir en sede extraordinaria. \u00a0\u00a0<\/p>\n<p>El \u00a0demandante \u00a0no \u00a0logra \u00a0percatarse que en \u00a0trat\u00e1ndose \u00a0de \u00a0la \u00a0casaci\u00f3n \u00a0discrecional, \u00a0dado el car\u00e1cter excepcional del \u00a0instrumento, \u00a0 resulta \u00a0 indispensable \u00a0 que \u00a0 en \u00a0 el \u00a0libelo \u00a0se \u00a0presente \u00a0la \u00a0fundamentaci\u00f3n \u00a0debida \u00a0frente a los motivos que determinan la viabilidad de la \u00a0admisi\u00f3n, \u00a0relacionada \u00a0con las posibilidades que para su interposici\u00f3n la ley \u00a0otorga, \u00a0 ya \u00a0 sea \u00a0 para \u00a0perseguir, \u00a0por \u00a0dicha \u00a0v\u00eda, \u00a0el \u00a0desarrollo \u00a0de \u00a0la \u00a0jurisprudencia \u00a0 o \u00a0 la \u00a0 garant\u00eda \u00a0de \u00a0un \u00a0derecho \u00a0fundamental \u00a0presuntamente \u00a0transgredido \u00a0en \u00a0las \u00a0instancias, \u00a0debiendo \u00a0precisar \u00a0clara y n\u00edtidamente, la \u00a0raz\u00f3n \u00a0o \u00a0razones \u00a0por \u00a0las \u00a0cuales \u00a0el Juez de casaci\u00f3n debe intervenir en un \u00a0asunto \u00a0 sobre \u00a0 el \u00a0 que \u00a0 no \u00a0 concurren \u00a0los \u00a0presupuestos \u00a0de \u00a0la \u00a0casaci\u00f3n \u00a0com\u00fan. \u00a0\u00a0<\/p>\n<p>De \u00a0manera que si el motivo de inconformidad \u00a0con \u00a0el \u00a0fallo \u00a0de \u00a0segundo \u00a0grado estriba en aducir la violaci\u00f3n de un derecho \u00a0fundamental, \u00a0el \u00a0casacionista \u00a0est\u00e1 \u00a0obligado a desarrollar una argumentaci\u00f3n \u00a0l\u00f3gica \u00a0dirigida \u00a0a \u00a0patentizar \u00a0el desacierto, siendo de su cargo demostrar el \u00a0desconocimiento \u00a0de \u00a0una garant\u00eda por haberse quebrantado la estructura b\u00e1sica \u00a0del \u00a0proceso \u00a0o la actividad del juzgador, e indicar las normas constitucionales \u00a0que \u00a0 protegen \u00a0 el \u00a0derecho \u00a0invocado \u00a0y \u00a0su \u00a0concreto \u00a0conculcamiento \u00a0con \u00a0la \u00a0sentencia.\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Si \u00a0lo \u00a0perseguido es un pronunciamiento con \u00a0criterio \u00a0de \u00a0autoridad \u00a0en \u00a0relaci\u00f3n \u00a0con \u00a0determinado punto jur\u00eddico que por \u00a0oscuro \u00a0merezca \u00a0ser \u00a0clarificado, \u00a0resulta indispensable que ello se diga en el \u00a0escrito \u00a0respectivo. \u00a0Debe \u00a0indicarse, \u00a0igualmente, \u00a0si \u00a0lo \u00a0que \u00a0se \u00a0pide es la \u00a0unificaci\u00f3n \u00a0de \u00a0posiciones \u00a0encontradas sobre el particular, la actualizaci\u00f3n \u00a0de \u00a0la \u00a0doctrina \u00a0hasta \u00a0el momento imperante o el pronunciamiento sobre un tema \u00a0a\u00fan \u00a0no \u00a0desarrollado. \u00a0Tambi\u00e9n \u00a0ha \u00a0de se\u00f1alarse de qu\u00e9 manera la decisi\u00f3n \u00a0demandada \u00a0de \u00a0la \u00a0Corte presta el doble servicio de solucionar adecuadamente el \u00a0caso \u00a0 y \u00a0 servir \u00a0 de \u00a0 gu\u00eda \u00a0 como \u00a0 criterio \u00a0 auxiliar \u00a0 de \u00a0 la \u00a0actividad \u00a0judicial. \u00a0\u00a0<\/p>\n<p>Compete al censor, asimismo, cumplir con los \u00a0requisitos \u00a0establecidos \u00a0en \u00a0el \u00a0art\u00edculo 212 de la ley 600 de 2000, entre los \u00a0que \u00a0se \u00a0incluye la necesidad de enunciar el motivo de casaci\u00f3n en que se apoya \u00a0la \u00a0demanda, \u00a0e \u00a0indicar \u00a0clara \u00a0y \u00a0precisamente \u00a0los \u00a0fundamentos \u00a0f\u00e1cticos \u00a0y \u00a0jur\u00eddicos \u00a0del \u00a0cargo \u00a0o cargos que se formulen, los cuales inexorablemente han \u00a0de \u00a0corresponder \u00a0a un desarrollo de las razones en que se funda la solicitud de \u00a0admisi\u00f3n de la v\u00eda discrecional. \u00a0\u00a0<\/p>\n<p>En todo caso, es competencia exclusiva de la \u00a0Corte, \u00a0 en \u00a0ejercicio \u00a0de \u00a0su \u00a0discrecionalidad, \u00a0ponderar \u00a0la \u00a0fundamentaci\u00f3n \u00a0expuesta \u00a0por \u00a0la \u00a0parte \u00a0que \u00a0acude \u00a0a dicho instrumento, y decidir si admite o \u00a0rechaza el tr\u00e1mite de la casaci\u00f3n excepcional. \u00a0\u00a0<\/p>\n<p>En este evento, nada dice el censor en torno \u00a0a \u00a0las razones que le animan a ejercer la casaci\u00f3n excepcional, ni su conexi\u00f3n \u00a0con \u00a0los \u00a0motivos \u00a0previstos \u00a0en \u00a0la \u00a0ley \u00a0que \u00a0determinan \u00a0la \u00a0viabilidad de su \u00a0admisi\u00f3n. \u00a0En lugar de ello, pasa por encima de dicho presupuesto y da un salto \u00a0a \u00a0la \u00a0postulaci\u00f3n \u00a0de \u00a0los \u00a0cargos \u00a0con apoyo en la causal primera, como si el \u00a0evento sub judice admitiera la v\u00eda com\u00fan de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Al margen de la anotada impropiedad de orden \u00a0t\u00e9cnico, \u00a0de \u00a0suyo \u00a0suficiente \u00a0para \u00a0inadmitir la demanda, es lo cierto que la \u00a0sustentaci\u00f3n \u00a0contenida \u00a0en \u00a0el \u00a0libelo \u00a0se \u00a0establece \u00a0que el primer motivo de \u00a0inconformidad \u00a0radica en la circunstancia de que su asistido haya sido condenado \u00a0a \u00a0pagar \u00a0por \u00a0concepto \u00a0de perjuicios morales la suma equivalente a veinticinco \u00a0(25) \u00a0salarios m\u00ednimos legales mensuales y dieciocho (18) salarios por concepto \u00a0de \u00a0los \u00a0materiales, los cuales, en criterio del censor, no aparecen acreditados \u00a0en la actuaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Desde \u00a0esta \u00a0perspectiva es claro que no hay \u00a0lugar \u00a0a \u00a0la \u00a0casaci\u00f3n \u00a0discrecional \u00a0pues \u00a0de acuerdo con el art\u00edculo 208 del \u00a0C\u00f3digo \u00a0de Procedimiento Penal, cuando el recurso tenga por objeto lo referente \u00a0a \u00a0la \u00a0indemnizaci\u00f3n \u00a0de \u00a0perjuicios \u00a0decretados \u00a0en la sentencia condenatoria, \u00a0deber\u00e1 \u00a0tener \u00a0como \u00a0fundamento \u00a0las \u00a0causales \u00a0y \u00a0la \u00a0cuant\u00eda \u00a0para \u00a0recurrir \u00a0establecidas \u00a0en las normas que regulan la casaci\u00f3n civil, sin consideraci\u00f3n a \u00a0la \u00a0pena \u00a0establecida \u00a0para el delito o delitos, y sobre este requisito no opera \u00a0la \u00a0discrecionalidad \u00a0que establece el inciso tercero del art\u00edculo 205 ejusdem, \u00a0pues, \u00a0como \u00a0la misma disposici\u00f3n lo advierte, la excepcionalidad s\u00f3lo resulta \u00a0procedente \u00a0respecto \u00a0de \u00a0aquellos eventos no cobijados por el inciso primero de \u00a0dicha \u00a0disposici\u00f3n, \u00a0tal y como ha sido declarado por la jurisprudencia de esta \u00a0Corte \u00a0(Cfr. \u00a0cas. \u00a0de \u00a0junio \u00a025 de 2002, rad. 18343 y cas. de sept. 23\/03 rad. \u00a020947). \u00a0\u00a0<\/p>\n<p>Y \u00a0a\u00fan \u00a0si \u00a0se entendiera que la censura se \u00a0orienta \u00a0a pregonar la existencia de una irregularidad sustancial con compromiso \u00a0del \u00a0debido \u00a0proceso, \u00a0no con el fin de atacar la existencia del hecho punible o \u00a0la \u00a0responsabilidad \u00a0del \u00a0procesado \u00a0sino \u00a0para \u00a0abrirle \u00a0camino \u00a0a su exclusiva \u00a0pretensi\u00f3n \u00a0de \u00a0controvertir \u00a0el \u00a0fundamento \u00a0jur\u00eddico \u00a0de \u00a0la condena por los \u00a0perjuicios \u00a0ocasionados \u00a0a \u00a0la \u00a0v\u00edctima, \u00a0resulta evidente que la alegaci\u00f3n no \u00a0pone \u00a0de \u00a0presente \u00a0la \u00a0configuraci\u00f3n \u00a0de \u00a0irritualidad \u00a0alguna, \u00a0sino, \u00a0por el \u00a0contrario, \u00a0se \u00a0dirige \u00a0a \u00a0cuestionar \u00a0la selecci\u00f3n por el juzgador de la norma \u00a0sustancial \u00a0con \u00a0apoyo \u00a0en \u00a0la cual se fij\u00f3 el monto de los da\u00f1os y perjuicios \u00a0ocasionados con el delito. \u00a0\u00a0<\/p>\n<p>En \u00a0este evento, tambi\u00e9n la inadmisi\u00f3n del \u00a0libelo \u00a0se ofrece obligada, y para ello es suficiente con se\u00f1alar que en virtud \u00a0de \u00a0la \u00a0integraci\u00f3n \u00a0que ordena el mencionado art\u00edculo 208 del C. de P. P., el \u00a0art\u00edculo \u00a0366 \u00a0del \u00a0C\u00f3digo \u00a0de Procedimiento Civil, subrogado por el art\u00edculo \u00a01\u00ba \u00a0de \u00a0la \u00a0Ley \u00a0592 \u00a0de \u00a02000,\u00a0 \u00a0establece la procedencia de la casaci\u00f3n \u00a0\u201ccuando \u00a0el \u00a0valor \u00a0actual \u00a0de la resoluci\u00f3n desfavorable al recurrente sea o \u00a0exceda \u00a0de \u00a0cuatrocientos \u00a0veinticinco (425) salarios m\u00ednimos legales mensuales \u00a0vigentes\u201d. \u00a0\u00a0<\/p>\n<p>Es \u00a0evidente, \u00a0por \u00a0tanto, que el demandante \u00a0carece \u00a0de inter\u00e9s para recurrir, pues la condena al pago de perjuicios morales \u00a0y \u00a0materiales \u00a0ascendi\u00f3 \u00a0a \u00a0cuarenta y tres salarios m\u00ednimos legales mensuales \u00a0vigentes, \u00a0lo \u00a0que \u00a0hace \u00a0improcedente \u00a0la casaci\u00f3n en las modalidades com\u00fan y \u00a0discrecional. \u00a0\u00a0<\/p>\n<p>Y \u00a0en \u00a0relaci\u00f3n \u00a0con \u00a0el \u00a0segundo cargo, el \u00a0censor \u00a0se \u00a0dedica \u00a0a \u00a0denunciar \u00a0que \u00a0los \u00a0juzgadores incurrieron en errores de \u00a0apreciaci\u00f3n \u00a0 probatoria, \u00a0pero \u00a0no \u00a0indica, \u00a0ni \u00a0por \u00a0supuesto \u00a0demuestra, \u00a0la \u00a0necesidad \u00a0de \u00a0intervenci\u00f3n \u00a0excepcional \u00a0de \u00a0la \u00a0Corte \u00a0para resguardar alguna \u00a0garant\u00eda \u00a0fundamental que hubiese resultado transgredida en la actuaci\u00f3n, o el \u00a0desarrollo \u00a0de \u00a0la \u00a0jurisprudencia \u00a0sobre alg\u00fan tema jur\u00eddico de trascendental \u00a0importancia, \u00a0 \u00a0 \u00a0 \u00a0 \u00fanicos \u00a0 \u00a0 \u00a0 \u00a0 motivos \u00a0 \u00a0 \u00a0 \u00a0que \u00a0 \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0 \u00a0har\u00edan \u00a0procedente.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Como \u00a0quiera \u00a0entonces \u00a0que \u00a0el casacionista \u00a0omite \u00a0fundamentar \u00a0clara \u00a0y precisamente los motivos que lo llevan a invocar el \u00a0ejercicio \u00a0de \u00a0la \u00a0discrecionalidad \u00a0por la Corte, y el primer cargo que formula \u00a0patentiza \u00a0la \u00a0ausencia \u00a0de inter\u00e9s para acudir en sede extraordinaria, resulta \u00a0inexorable \u00a0tener \u00a0que \u00a0inadmitir \u00a0la \u00a0demanda \u00a0y \u00a0disponer \u00a0la \u00a0devoluci\u00f3n del \u00a0diligenciamiento al\u00a0 Juzgado de origen. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0LA \u00a0CORTE \u00a0SUPREMA DE JUSTICIA, SALA DE CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>R E S U E L V E: \u00a0<\/p>\n<p>INADMITIR \u00a0 la \u00a0demanda \u00a0 de \u00a0 casaci\u00f3n \u00a0discrecional \u00a0presentada \u00a0por \u00a0el \u00a0defensor \u00a0del\u00a0 \u00a0procesado LUIS ATAULFO T\u00c9LLEZ JIM\u00c9NEZ. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta \u00a0providencia no procede recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese \u00a0y \u00a0devu\u00e9lvase \u00a0al Despacho de \u00a0origen. \u00a0\u00a0<\/p>\n<p>C\u00famplase. \u00a0<\/p>\n<p>HERMAN \u00a0 \u00a0GAL\u00c1N \u00a0CASTELLANOS \u00a0\u00a0<\/p>\n<p>SIGIFREDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ESPINOSA \u00a0P\u00c9REZ\u00a0\u00a0\u00a0\u00a0 ALFREDO G\u00d3MEZ QUINTERO \u00a0\u00a0<\/p>\n<p>EDGAR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 LOMBANA \u00a0TRUJILLO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0ALVARO \u00a0 O. \u00a0 P\u00c9REZ \u00a0PINZ\u00d3N \u00a0\u00a0<\/p>\n<p>MARINA \u00a0 \u00a0 \u00a0 \u00a0PULIDO \u00a0 \u00a0 \u00a0 \u00a0DE \u00a0BAR\u00d3N\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0JORGE \u00a0 \u00a0 \u00a0 \u00a0L. \u00a0 \u00a0 \u00a0 QUINTERO \u00a0MILAN\u00c9S \u00a0\u00a0<\/p>\n<p>YESID \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 RAM\u00cdREZ \u00a0BASTIDAS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0MAURO SOLARTE PORTILLA \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 22277 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACION PENAL \u00a0 Magistrado Ponente: \u00a0 Dr. \u00a0 MAURO \u00a0 SOLARTE \u00a0PORTILLA \u00a0\u00a0 Aprobado acta No. 079 \u00a0 Bogot\u00e1, D. C., veintid\u00f3s de septiembre del \u00a0a\u00f1o dos mil cuatro. \u00a0\u00a0 Se pronuncia la Corte sobre la admisibilidad \u00a0de \u00a0la \u00a0demanda \u00a0de casaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-8951","post","type-post","status-publish","format-standard","hentry","category-12"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/8951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=8951"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/8951\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=8951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=8951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=8951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}