{"id":7730,"date":"2023-09-08T17:01:25","date_gmt":"2023-09-08T17:01:25","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2069127-05-03\/"},"modified":"2023-09-08T17:01:25","modified_gmt":"2023-09-08T17:01:25","slug":"2069127-05-03","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2069127-05-03\/","title":{"rendered":"20691(27-05-03)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 20691 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>Dr. CARLOS AUGUSTO G\u00c1LVEZ AREGOTE \u00a0<\/p>\n<p>Aprobado Acta No. 58 \u00a0<\/p>\n<p>Bogot\u00e1, D.C., veintisiete (27) de mayo de dos \u00a0mil tres (2.003). \u00a0\u00a0<\/p>\n<p>VISTOS: \u00a0<\/p>\n<p>Se pronuncia la Sala sobre la admisibilidad de \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0a \u00a0nombre \u00a0de MARLENE ZULETA GUTI\u00c9RREZ, \u00a0contra \u00a0la \u00a0sentencia \u00a0proferida \u00a0el \u00a015 \u00a0de \u00a0octubre \u00a0de \u00a02.002 por el Tribunal \u00a0Superior \u00a0de \u00a0Valledupar \u00a0que \u00a0confirm\u00f3 \u00a0la dictada en primera instancia por el \u00a0Juzgado \u00a0Segundo \u00a0Penal \u00a0del \u00a0Circuito \u00a0de esa misma ciudad, mediante la cual se \u00a0conden\u00f3 \u00a0a \u00a0dicha \u00a0procesada \u00a0a \u00a0las penas principales de 6 a\u00f1os de prisi\u00f3n y \u00a0multa \u00a0 de \u00a040 \u00a0salarios \u00a0m\u00ednimos \u00a0mensuales \u00a0vigentes \u00a0y \u00a0a \u00a0la \u00a0accesoria \u00a0de \u00a0interdicci\u00f3n \u00a0de \u00a0derechos \u00a0y \u00a0funciones \u00a0p\u00fablicas \u00a0por \u00a0el \u00a0mismo lapso de la \u00a0sanci\u00f3n \u00a0restrictiva \u00a0de \u00a0la \u00a0libertad, \u00a0como autora del delito de celebraci\u00f3n \u00a0indebida \u00a0de \u00a0contratos. \u00a0En \u00a0el mismo fallo fueron tambi\u00e9n condenados, pero en \u00a0calidad \u00a0de \u00a0c\u00f3mplices \u00a0de \u00a0id\u00e9ntica \u00a0infracci\u00f3n, \u00a0Sa\u00fal \u00a0Oliveros \u00a0Ulloque y \u00a0Gabriel Alfonso Rosado Maestre. \u00a0\u00a0<\/p>\n<p>HECHOS: \u00a0<\/p>\n<p>As\u00ed los present\u00f3 el Tribunal: \u00a0<\/p>\n<p>\u201cLa \u00a0presente investigaci\u00f3n se inici\u00f3 con \u00a0base \u00a0en \u00a0la \u00a0denuncia \u00a0penal \u00a0formulada \u00a0contra \u00a0Marlene \u00a0Zuleta Guti\u00e9rrez por \u00a0irregularidades \u00a0 en \u00a0 el \u00a0ejercicio \u00a0del \u00a0cargo \u00a0de \u00a0Secretaria \u00a0de \u00a0Educaci\u00f3n \u00a0Departamental \u00a0del \u00a0Cesar, \u00a0a quien se le atribuy\u00f3 la violaci\u00f3n al r\u00e9gimen de \u00a0contrataci\u00f3n \u00a0administrativa \u00a0contemplado \u00a0en la Ley 80 de 1,993, al proceder a \u00a0contratar \u00a0con \u00a0el \u00a0mismo \u00a0objeto \u00a0por \u00a0la \u00a0suma de novecientos setenta millones \u00a0quinientos \u00a0cuarenta \u00a0y \u00a0tres \u00a0mil \u00a0setecientos \u00a0cincuenta \u00a0pesos, \u00a0mediante \u00a0el \u00a0fraccionamiento \u00a0en \u00a0ocho \u00a0contratos \u00a0para \u00a0eludir \u00a0el \u00a0proceso \u00a0de \u00a0licitaci\u00f3n \u00a0requerido\u201d. \u00a0\u00a0<\/p>\n<p>LA DEMANDA: \u00a0<\/p>\n<p>Con sustento en el cuerpo segundo de la causal \u00a0primera \u00a0de \u00a0casaci\u00f3n, \u00a0acusa la demandante el fallo de segundo grado de violar \u00a0indirectamente \u00a0la \u00a0ley sustancial, por error en la apreciaci\u00f3n de las pruebas, \u00a0ya \u00a0que a algunas de ellas y a todas en conjunto, les otorg\u00f3 un valor \u201cque no \u00a0corresponde \u00a0a \u00a0su contenido f\u00e1ctico\u201d, es decir, incurri\u00f3 en falso juicio de \u00a0identidad. \u00a0\u00a0<\/p>\n<p>De no haber mediado los yerros denunciados, el \u00a0sentenciador \u00a0habr\u00eda \u00a0concluido que la conducta desarrollada por MARLENE ZULETA \u00a0estuvo \u00a0determinada \u00a0por \u00a0el \u00a0error \u00a0en \u00a0que \u00a0fue determinada por Sa\u00fal Oliveros \u00a0Ulloque \u00a0y \u00a0Gabriel \u00a0Alfonso \u00a0Rosado \u00a0Maestre, quienes intervinieron en la etapa \u00a0contractual, \u00a0todo ello debido a que no valor\u00f3 la prueba en conjunto y conforme \u00a0a \u00a0las \u00a0reglas \u00a0de \u00a0la sana cr\u00edtica, desatendiendo lo dispuesto en el art\u00edculo \u00a0238 \u00a0del Estatuto Procesal de entonces. Por eso, adem\u00e1s, considera exagerada la \u00a0teor\u00eda \u00a0del \u00a0dominio \u00a0del \u00a0hecho \u00a0aplicada \u00a0en \u00a0este \u00a0caso para entender que su \u00a0defendida \u00a0 \u00a0es \u00a0 \u00a0part\u00edcipe \u00a0 \u00a0del \u00a0 \u00a0delito \u00a0 \u00a0por \u00a0 \u00a0haber \u00a0 \u00a0suscrito \u00a0 los \u00a0contratos. \u00a0\u00a0<\/p>\n<p>Quebrant\u00f3, pues, el fallador el art\u00edculo 232 \u00a0del \u00a0C\u00f3digo \u00a0de Procedimiento Penal, pues dict\u00f3 sentencia sin que obrara en el \u00a0proceso \u00a0prueba \u00a0que \u00a0condujera \u00a0a \u00a0la \u00a0certeza \u00a0sobre \u00a0la conducta punible y la \u00a0responsabilidad de la sindicada. \u00a0\u00a0<\/p>\n<p>En \u00a0este asunto, MAERLENE ZULETA recibi\u00f3 una \u00a0documentaci\u00f3n \u00a0de \u00a0un proceso precontractual y estim\u00f3 confiada que se ajustaba \u00a0al \u00a0marco legal, precisamente por provenir de funcionarios de la administraci\u00f3n \u00a0con \u00a0experiencia en el manejo de esta clase de asuntos, pues como lo expres\u00f3 en \u00a0la \u00a0indagatoria, \u00a0Oliveros \u00a0Ulloque, \u00a0asesor \u00a0Externo \u00a0de \u00a0la \u00a0Gobernaci\u00f3n, \u00a0le \u00a0sugiri\u00f3 \u00a0 decretar \u00a0 la \u00a0urgencia \u00a0manifiesta \u00a0para \u00a0solucionar \u00a0los \u00a0problemas \u00a0educativos \u00a0del Cesar. Por ese mismo motivo, revis\u00f3 los documentos que recibi\u00f3 \u00a0e \u00a0hizo \u00a0las \u00a0observaciones \u00a0del \u00a0caso seleccionando finalmente y conforme a los \u00a0principios \u00a0 que \u00a0 rigen \u00a0 la \u00a0contrataci\u00f3n \u00a0Estatal, \u00a0la \u00a0propuesta \u00a0que \u00a0m\u00e1s \u00a0favorablemente \u00a0se ajustaba a la administraci\u00f3n. El mismo Oliveros Ulloque, fue \u00a0quien \u00a0tambi\u00e9n \u00a0sugiri\u00f3 \u00a0que \u00a0se estableciera un t\u00e9rmino fijo de seis meses a \u00a0efectos \u00a0de \u00a0permitir \u00a0adquirir \u00a0mercanc\u00eda de buena calidad, adem\u00e1s, porque se \u00a0trataba de 25 municipios m\u00e1s la capital. \u00a0\u00a0<\/p>\n<p>Del \u00a0mismo \u00a0modo, \u00a0Gabriel \u00a0Alfonso \u00a0Rosado \u00a0Maestre, \u00a0persona \u00a0con \u00a0experiencia \u00a0y \u00a0conocimiento \u00a0de \u00a0la problem\u00e1tica de la \u00a0educaci\u00f3n \u00a0incidi\u00f3 \u00a0en las recomendaciones \u201cpara estructurar el error en que \u00a0incurri\u00f3 \u00a0mi \u00a0representada\u201d \u00a0y \u00a0en estos casos, es el sujeto de atr\u00e1s el que \u00a0dirige \u00a0el \u00a0acontecer \u00a0hacia el resultado final. Aqui, Oliveros Ulloque, contaba \u00a0con \u00a0los \u00a0conocimientos \u00a0suficientes para mover la voluntad de ELIZABETH, siendo \u00a0\u00e9l, \u00a0por \u00a0cinsiguiente, \u00a0quien \u00a0estaba \u00a0en \u00a0condiciones \u00a0de \u00a0dirigir \u00a0el \u00a0curso \u00a0causal. \u00a0\u00a0<\/p>\n<p>Adicionalmente, \u00a0como \u00a0MARLENE \u00a0ZULETA \u00a0solo \u00a0hab\u00eda \u00a0hecho \u00a0visitas \u00a0de \u00a0control \u00a0y \u00a0evaluaci\u00f3n a los centros educativos sin \u00a0tener \u00a0injerencia en la adquisici\u00f3n de bienes o servicios, \u201cno exist\u00eda en su \u00a0conciencia \u00a0la \u00a0desvalorizaci\u00f3n \u00a0social de su conducta, y mucho menos captar el \u00a0sentido \u00a0de \u00a0prohibici\u00f3n \u00a0y \u00a0en \u00a0esa \u00a0medida \u00a0actu\u00f3 \u00a0a ciegas\u201d. Pero como el \u00a0sentenciador \u00a0no \u00a0valor\u00f3 \u00a0los \u00a0testimonios \u00a0conforme \u00a0a \u00a0las \u00a0reglas de la sana \u00a0cr\u00edtica \u00a0no \u00a0le \u00a0reconoci\u00f3 \u00a0la \u00a0causal de ausencia de responsabilidad a que se \u00a0contrae el art\u00edculo 32.10 del C\u00f3digo Penal. \u00a0\u00a0<\/p>\n<p>Concluye, sin embargo, que ha formulado \u201cdos \u00a0cargos\u201d \u00a0 \u00a0 por \u00a0 \u00a0 violaci\u00f3n \u00a0 \u00a0indirecta \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0ley \u00a0 \u00a0\u2013art\u00edculo \u00a0 \u00a0277 \u00a0 del \u00a0 C\u00f3digo \u00a0 de \u00a0Procedimiento \u00a0Penal-\u00a0 \u00a0\u201cpor \u00a0error \u00a0de \u00a0hecho \u00a0al \u00a0no tener en cuenta el \u00a0alcance de la prueba legalmente producida\u201d . \u00a0\u00a0<\/p>\n<p>Solicita entonces, se case el fallo impugnado \u00a0y se dicte el que en su lugar deba reemplazarlo. \u00a0\u00a0<\/p>\n<p>ALEGATO DEL NO RECURRENTE: \u00a0<\/p>\n<p>En \u00a0 el \u00a0t\u00e9rmino \u00a0de \u00a0traslado \u00a0a \u00a0los \u00a0no \u00a0recurrentes \u00a0el \u00a0apoderado \u00a0de \u00a0Gabriel \u00a0Alfonso \u00a0Rosado \u00a0Maestre \u00a0present\u00f3 una \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0en \u00a0la \u00a0cual \u00a0postula \u00a0sendos \u00a0cargos contra el fallo de \u00a0segundo \u00a0grado \u00a0al \u00a0amparo \u00a0de \u00a0las \u00a0causales tercera y primera, aduciendo en el \u00a0primero \u00a0la violaci\u00f3n al derecho de defensa por deficiente interrogatorio en la \u00a0indagatoria, \u00a0y \u00a0en \u00a0el \u00a0segundo, \u00a0una \u00a0violaci\u00f3n \u00a0directa de la ley sustancial \u00a0\u201cpor \u00a0error \u00a0de \u00a0derecho\u201d, \u00a0por \u00a0no \u00a0existir \u00a0prueba \u00a0en \u00a0el \u00a0proceso que lo \u00a0incrimine como c\u00f3mplice. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES: \u00a0<\/p>\n<p>1. \u00a0La \u00a0demanda \u00a0presentada \u00a0a \u00a0nombre \u00a0de la \u00a0procesada \u00a0MARLENE \u00a0ZULETA \u00a0GUTI\u00c9RREZ \u00a0contiene \u00a0serias \u00a0deficiencias \u00a0de orden \u00a0t\u00e9cnico \u00a0y \u00a0argumentativo \u00a0tanto \u00a0en \u00a0la \u00a0proposici\u00f3n de la censura como en su \u00a0desarrollo, \u00a0todo \u00a0lo \u00a0cual redunda en un claro desconocimiento del requisito de \u00a0precisi\u00f3n \u00a0y \u00a0claridad \u00a0exigido en la confecci\u00f3n formal del libelo (art. 212.3 \u00a0del C.P.) que, a no dudarlo, imponen su desestimaci\u00f3n. \u00a0\u00a0<\/p>\n<p>2. Es as\u00ed como, no obstante referir al final \u00a0del \u00a0escrito \u00a0que \u00a0ha propuesto dos cargos contra el fallo impugnado, la Sala no \u00a0advierte \u00a0sino \u00a0uno \u00a0defectuosamente \u00a0propuesto, sin que tampoco de su equ\u00edvoca \u00a0fundamentaci\u00f3n \u00a0se \u00a0advierta \u00a0la \u00a0presencia \u00a0de \u00a0otro reparo que pueda al menos \u00a0tener \u00a0 entidad \u00a0 suficiente \u00a0 para \u00a0 entenderlo \u00a0 aut\u00f3noma \u00a0 e \u00a0 independiente \u00a0postulado. \u00a0\u00a0<\/p>\n<p>3. \u00a0En \u00a0efecto, \u00a0el \u00a0demandante \u00a0acusa \u00a0una \u00a0violaci\u00f3n \u00a0indirecta \u00a0de la ley pero no concreta el sentido del quebranto, esto \u00a0es, \u00a0si \u00a0por \u00a0aplicaci\u00f3n indebida o falta de aplicaci\u00f3n. Adem\u00e1s, aduce que el \u00a0fallador \u00a0incurri\u00f3 \u00a0en \u00a0errores de hecho por falsos juicios de identidad porque \u00a0no \u00a0 valor\u00f3 \u00a0 la \u00a0 prueba \u00a0 en \u00a0 conjunto, \u00a0es \u00a0decir, \u00a0parte \u00a0de \u00a0una \u00a0premisa \u00a0contradictoria, \u00a0ya \u00a0que \u00a0lo \u00a0primero \u00a0no supone lo segundo sino que lo excluye, \u00a0pues \u00a0una \u00a0cosa \u00a0es \u00a0apreciar \u00a0la prueba y en ese proceso evaluativo incurrir en \u00a0distorsiones \u00a0frente \u00a0a \u00a0su contenido objetivo, y otra muy distinta escoger como \u00a0sustento \u00a0de \u00a0la \u00a0decisi\u00f3n \u00a0unos \u00a0elementos de convicci\u00f3n con la exclusi\u00f3n de \u00a0otros. \u00a0Eso, \u00a0necesariamente \u00a0significa \u00a0que las deducciones del sentenciador no \u00a0corresponden \u00a0a \u00a0lo probado porque omiti\u00f3 el an\u00e1lisis de medios trascendentes, \u00a0lo \u00a0que \u00a0en \u00a0t\u00e9cnica \u00a0de \u00a0casaci\u00f3n no es nada distinto a un error de hecho por \u00a0falso \u00a0juicio \u00a0de \u00a0existencia. \u00a0Al \u00a0mismo \u00a0tiempo, mezcla postulados propios del \u00a0error \u00a0de \u00a0hecho \u00a0por falso raciocinio en la medida en que se queja de que no se \u00a0hubieran \u00a0aplicado \u00a0las \u00a0reglas \u00a0de la sana cr\u00edtica, pero \u00e9sta, no es m\u00e1s que \u00a0una \u00a0gen\u00e9rica \u00a0y \u00a0suelta \u00a0afirmaci\u00f3n que tampoco encuentra demostraci\u00f3n en la \u00a0demanda. \u00a0\u00a0<\/p>\n<p>4. De todas maneras, la inconsistencia de tal \u00a0predicado \u00a0es \u00a0insalvable, toda vez que el recurrente no se\u00f1ala de ning\u00fan modo \u00a0cu\u00e1les \u00a0son \u00a0las pruebas objeto del error y en qu\u00e9 sentido se produjo el mismo \u00a0en \u00a0relaci\u00f3n \u00a0con cada una de ellas, y tampoco ning\u00fan esfuerzo se advierte por \u00a0acreditar, \u00a0a \u00a0partir \u00a0del sustento probatorio del fallo, cu\u00e1l es la incidencia \u00a0del \u00a0desatino \u00a0en \u00a0la \u00a0decisi\u00f3n \u00a0final y de qu\u00e9 manera, de no mediar el mismo, \u00a0habr\u00eda variado los razonamientos que la soportaron. \u00a0\u00a0<\/p>\n<p>5. Pero adem\u00e1s, el discurso argumentativo del \u00a0libelista \u00a0se \u00a0remite a sostener, con apoyo en la teor\u00eda del dominio del hecho, \u00a0que \u00a0la \u00a0responsabilidad \u00a0penal \u00a0debe \u00a0recaer en los coprocesados Sa\u00fal Oliveros \u00a0Ulloque \u00a0y \u00a0Alfonso \u00a0Rosado \u00a0Maestre \u00a0por \u00a0ser \u00a0las personas que la indujeron en \u00a0error, \u00a0 afirmando \u00a0 claramente, \u00a0y \u00a0as\u00ed \u00a0finalmente \u00a0concreta \u00a0la \u00a0pretensi\u00f3n \u00a0casacional, \u00a0que \u00a0MARLENE \u00a0actu\u00f3 \u00a0sin culpabilidad por cuanto su comportamiento \u00a0estuvo \u00a0determinado \u00a0por \u00a0el \u00a0error \u00a0en \u00a0que \u00a0la hicieron incurrir aquellos. Sin \u00a0embargo, \u00a0contradictoriamente \u00a0sostiene que se le conden\u00f3 sin que en el proceso \u00a0existiera \u00a0 prueba \u00a0 que \u00a0 condujera \u00a0a \u00a0la \u00a0certeza \u00a0del \u00a0hecho \u00a0punible \u00a0y \u00a0la \u00a0responsabilidad \u00a0de \u00a0la \u00a0sindicada. \u00a0En estas condiciones, la orientaci\u00f3n de la \u00a0censura \u00a0pareciera \u00a0estar al tiempo dirigida en dos sentidos contrarios, pues el \u00a0error \u00a0excluyente \u00a0de \u00a0responsabilidad \u00a0supone certeza tanto sobre la ocurrencia \u00a0del \u00a0hecho \u00a0como \u00a0de \u00a0la \u00a0responsabilidad, \u00a0mientras \u00a0que \u00a0lo \u00a0segundo, niega la \u00a0demostraci\u00f3n \u00a0 de \u00a0 esos \u00a0 dos \u00a0supuestos \u00a0en \u00a0el \u00a0aludido \u00a0grado \u00a0\u2013de \u00a0certeza- e impone el reconocimiento \u00a0del \u00a0in \u00a0dubio pro reo, en tanto que lo que se configurar\u00eda ser\u00eda una duda que \u00a0debe favorecer a la procesada. \u00a0\u00a0<\/p>\n<p>6. \u00a0A la postre, no demuestra el casacionista \u00a0ning\u00fan \u00a0yerro capaz de propiciar la ruptura del fallo, reduci\u00e9ndose su alegato \u00a0a \u00a0una \u00a0manifestaci\u00f3n \u00a0de inconformidad sobre el valor probatorio otorgado a la \u00a0versi\u00f3n exculpativa de MARLENE ZULETA GUTI\u00c9RREZ. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>7. De otra parte, esto es, en relaci\u00f3n con el \u00a0alegato \u00a0del \u00a0no \u00a0recurrente, \u00a0encuentra \u00a0la \u00a0Sala \u00a0oportuno \u00a0dejar en claro que \u00a0ning\u00fan \u00a0comentario \u00a0amerita \u00a0por \u00a0cuanto, lejos de remitirse al contenido de la \u00a0demanda, \u00a0constituye \u00a0un \u00a0libelo \u00a0extempor\u00e1neo \u00a0a \u00a0favor \u00a0del procesado Gabriel \u00a0Alfonso \u00a0Rosado \u00a0Maestre, \u00a0si \u00a0se \u00a0tiene \u00a0en \u00a0cuente \u00a0que \u00a0dicho sindicado ni su \u00a0defensor interpusieron en tiempo el recurso extraordinario. \u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la CORTE SUPREMA DE \u00a0JUSTICIA, SALA DE CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>1. \u00a0 Inadmitir \u00a0 la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0interpuesta por el defensor de MARLENE ZULETA GUTI\u00c9RREZ. \u00a0\u00a0<\/p>\n<p>2. \u00a0Contra \u00a0esta decisi\u00f3n no procede recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0 notif\u00edquese, \u00a0 c\u00famplase \u00a0 y \u00a0devu\u00e9lvase al Tribunal de origen. \u00a0\u00a0<\/p>\n<p>YESID RAM\u00cdREZ BASTIDAS \u00a0<\/p>\n<p>FERNANDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 ARBOLEDA \u00a0RIPOLL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0HERMAN GAL\u00c1N \u00a0CASTELLANOS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 \u00a0 \u00a0 AUGUSTO \u00a0 \u00a0 \u00a0 G\u00c1LVEZ \u00a0ARGOTE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JORGE \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 AN\u00cdBAL \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 G\u00d3MEZ \u00a0GALLEGO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>EDGAR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0LOMBANA \u00a0TRUJILLO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00c1LVARO \u00a0ORLANDO \u00a0P\u00c9REZ PINZ\u00d3N\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Comisi\u00f3n de servicio \u00a0<\/p>\n<p>MARINA \u00a0 \u00a0 \u00a0 \u00a0PULIDO \u00a0 \u00a0 \u00a0 \u00a0DE \u00a0BAR\u00d3N\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JORGE LUIS QUINTERO MILAN\u00c9S \u00a0\u00a0<\/p>\n<p>Teresa Ruiz N\u00fa\u00f1ez \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 20691 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente: \u00a0 Dr. CARLOS AUGUSTO G\u00c1LVEZ AREGOTE \u00a0 Aprobado Acta No. 58 \u00a0 Bogot\u00e1, D.C., veintisiete (27) de mayo de dos \u00a0mil tres (2.003). \u00a0\u00a0 VISTOS: \u00a0 Se pronuncia la Sala sobre la admisibilidad de \u00a0la \u00a0demanda \u00a0de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-7730","post","type-post","status-publish","format-standard","hentry","category-11"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/7730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=7730"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/7730\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=7730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=7730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=7730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}