{"id":7370,"date":"2023-09-08T17:01:04","date_gmt":"2023-09-08T17:01:04","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1994727-03-03\/"},"modified":"2023-09-08T17:01:04","modified_gmt":"2023-09-08T17:01:04","slug":"1994727-03-03","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1994727-03-03\/","title":{"rendered":"19947(27-03-03)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 19947 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0Dr. YESID RAM\u00cdREZ BASTIDAS \u00a0\u00a0<\/p>\n<p>Aprobado Acta No. 038 \u00a0<\/p>\n<p>Bogot\u00e1 D.C., veintisiete (27) de marzo de dos \u00a0mil tres\u00a0 (2003). \u00a0\u00a0<\/p>\n<p>V I S T O S: \u00a0<\/p>\n<p>Decide \u00a0la Sala sobre la demanda de casaci\u00f3n \u00a0presentada \u00a0por \u00a0el apoderado de la parte civil dentro del proceso adelantado en \u00a0contra \u00a0de \u00a0RAFAEL \u00a0GUILLERMO \u00a0ARENAS \u00a0\u00c1LVAREZ \u00a0por la presunta comisi\u00f3n de la \u00a0conducta punible de estafa. \u00a0\u00a0<\/p>\n<p>HECHOS: \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0RAFAEL \u00a0GUILLERMO ARENAS \u00c1LVAREZ decidi\u00f3 rifar la camioneta Mazda, \u00a0l\u00ednea \u00a0B-2000, de placas BJ &#8211; 813, color rojo montana de su propiedad, pagadera \u00a0a \u00a0quien \u00a0adquiriera \u00a0la \u00a0boleta \u00a0con \u00a0el \u00a0n\u00famero \u00a0que \u00a0coincidiera con las dos \u00a0\u00faltimas \u00a0cifras \u00a0del \u00a0que \u00a0resultara ganador del premio mayor de la loter\u00eda de \u00a0Bogot\u00e1 \u00a0que \u00a0jugaba \u00a0el \u00a06 \u00a0de \u00a0julio \u00a0de \u00a01995.\u00a0 Carolina Mar\u00edn M\u00e9ndez, \u00a0cu\u00f1ada \u00a0suya \u00a0que \u00a0le \u00a0colabor\u00f3 con la venta de boletas, dej\u00f3 para s\u00ed la del \u00a0n\u00famero \u00a0 \u00a006 \u00a0 que \u00a0 resultara \u00a0 ganador \u00a0 del \u00a0 sorteo, \u00a0 entreg\u00e1ndosele \u00a0 el \u00a0veh\u00edculo.\u00a0 \u00a0Posteriormente \u00a0y \u00a0durante \u00a0m\u00e1s \u00a0de un mes, la se\u00f1ora Mar\u00edn \u00a0intent\u00f3 \u00a0infructuosamente \u00a0venderlo, \u00a0aceptando \u00a0finalmente la oferta de compra \u00a0por \u00a0ocho \u00a0millones de pesos ($8.000.000.oo) que le hizo quien la hab\u00eda rifado, \u00a0recibiendo \u00a0un \u00a0adelanto \u00a0de \u00a0un mill\u00f3n ciento cincuenta y dos mil pesos.\u00a0 \u00a0ARENAS \u00a0\u00c1LVAREZ \u00a0se neg\u00f3 a pagarle el resto del dinero, alegando que como ella \u00a0no \u00a0hab\u00eda \u00a0cancelado previamente al sorteo la boleta que resultara ganadora, no \u00a0ten\u00eda derecho a reclamar el premio. \u00a0\u00a0<\/p>\n<p>ANTECEDENTES: \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01. \u00a0La \u00a0Fiscal\u00eda \u00a0General \u00a0de \u00a0la Naci\u00f3n \u00a0dispuso \u00a0apertura \u00a0de \u00a0instrucci\u00f3n y adelant\u00f3 el tr\u00e1mite hasta el 30 de marzo \u00a0de \u00a01998 \u00a0cuando \u00a0profiri\u00f3 \u00a0resoluci\u00f3n de acusaci\u00f3n en\u00a0 contra de RAFAEL \u00a0GUILERMO \u00a0ARENAS \u00a0\u00c1LVAREZ \u00a0como \u00a0presunto \u00a0responsable \u00a0del \u00a0delito \u00a0de estafa, \u00a0agravada por la cuant\u00eda. \u00a0\u00a0<\/p>\n<p>2. \u00a0 Mediante \u00a0sentencia \u00a0del \u00a05 \u00a0de \u00a0febrero \u00a0de \u00a02001 \u00a0el \u00a0Juzgado 10\u00b0 Penal del Circuito de \u00a0Bogot\u00e1 \u00a0D.C. \u00a0conden\u00f3 \u00a0al \u00a0acusado \u00a0a \u00a0las \u00a0penas \u00a0principales \u00a0de 24 meses de \u00a0prisi\u00f3n \u00a0y multa de cinco mil pesos como autor responsable del delito motivo de \u00a0la acusaci\u00f3n.\u00a0 \u00a0\u00a0<\/p>\n<p>3. \u00a0Contra \u00a0esa \u00a0sentencia \u00a0interpuso \u00a0recurso \u00a0de \u00a0apelaci\u00f3n el defensor del procesado, que fue \u00a0desatado \u00a0mediante \u00a0fallo del 23 de abril de 2002 por la Sala Penal del Tribunal \u00a0Superior \u00a0del \u00a0Distrito \u00a0Judicial \u00a0de \u00a0Bogot\u00e1 \u00a0D.C. \u00a0revocando \u00a0la sentencia de \u00a0primera instancia para en su lugar absolver al acusado. Y, \u00a0\u00a0<\/p>\n<p>4. El apoderado de \u00a0la \u00a0parte \u00a0civil \u00a0interpuso el recurso extraordinario de casaci\u00f3n que sustent\u00f3 \u00a0como a continuaci\u00f3n se sintetiza. \u00a0\u00a0<\/p>\n<p>LA DEMANDA: \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Se \u00a0presenta \u00a0con \u00a0fundamento \u00a0en la causal primera, cuerpo segundo, \u00a0del \u00a0art\u00edculo 207 del C\u00f3digo de Procedimiento Penal, bajo cargos de violaci\u00f3n \u00a0indirecta \u00a0de \u00a0la \u00a0ley \u00a0sustancial \u00a0por \u00a0error \u00a0de hecho derivado de equivocados \u00a0juicios \u00a0que \u00a0indujeron \u00a0al \u00a0fallador \u00a0a no aplicar el art\u00edculo 356 del C\u00f3digo \u00a0Penal, \u00a0que concretamente ocurrieron porque los Magistrados de la Sala Penal del \u00a0Tribunal Superior del Distrito Judicial de Bogot\u00e1 D.C. \u00a0\u00a0<\/p>\n<p>\u201cincurren en error de l\u00f3gica jur\u00eddica al \u00a0estructurar \u00a0juicios \u00a0de \u00a0inferencia \u00a0no \u00a0compatibles \u00a0con la realidad debido al \u00a0empleo de premisas desafortunadas\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Para \u00a0desarrollar \u00a0esa \u00a0afirmaci\u00f3n, \u00a0el \u00a0censor \u00a0transcribe algunos \u00a0apartes \u00a0del \u00a0fallo \u00a0del \u00a0Tribunal, \u00a0glos\u00e1ndolos \u00a0con \u00a0comentarios de su propio \u00a0tenor. \u00a0As\u00ed, \u00a0a \u00a0la afirmaci\u00f3n conclusiva del ad quem sobre un acuerdo de pago \u00a0posterior \u00a0de la boleta que result\u00f3 ganadora entre el acusado y su denunciante, \u00a0del \u00a0que \u00a0aqu\u00e9l \u00a0finalmente \u00a0se arrepinti\u00f3 y por ello no le pag\u00f3 la totalidad \u00a0del \u00a0precio \u00a0del veh\u00edculo que le hab\u00eda comprado, contrapone que ese acuerdo de \u00a0compraventa \u00a0del \u00a0automotor \u00a0que \u00a0aquella \u00a0supuestamente \u00a0se hab\u00eda ganado en la \u00a0rifa,\u00a0 \u00a0fue \u00a0una \u00a0treta \u00a0que \u00a0el \u00a0acusado \u00a0\u201cmaquin\u00f3, \u00a0ide\u00f3, \u00a0fabul\u00f3 \u00a0y \u00a0dise\u00f1\u00f3\u201d \u00a0para \u00a0despojarla \u00a0del \u00a0mismo y que la cuota inicial que le cancel\u00f3 \u00a0del \u00a0precio \u00a0acordado, \u00a0fue un ardid para llenarla de confianza y convencerla de \u00a0que ten\u00eda la intenci\u00f3n de cumplir con el contrato. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0A \u00a0continuaci\u00f3n \u00a0se pregunta, c\u00f3mo explicar que ARENAS \u00c1LVAREZ le \u00a0haya \u00a0entregado el veh\u00edculo a la denunciante, sino es por el acuerdo de pago de \u00a0la \u00a0boleta ganadora con posterioridad a la fecha de la rifa, pues de no existir, \u00a0el \u00a0encausado no hubiera realizado un contrato de compraventa de la camioneta, y \u00a0de \u00a0esa \u00a0manera \u00a0reconoci\u00f3 \u00a0la \u00a0propiedad \u00a0de ella sobre ese automotor. Con ese \u00a0comportamiento \u00a0\u2013dice \u00a0el \u00a0censor\u2014 \u00a0 el \u00a0procesado \u00a0exterioriz\u00f3 \u00a0su \u00a0dolo, pues sab\u00eda que con esa conducta lesionaba el patrimonio \u00a0de la denunciante. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Era \u00a0 entonces \u00a0 imperioso \u00a0para \u00a0el \u00a0Tribunal \u00a0dar \u00a0aplicaci\u00f3n \u00a0al \u00a0art\u00edculo \u00a0356 del C\u00f3digo Penal (derogado) y no revocar la sentencia de primera \u00a0instancia, \u00a0pues \u00a0al conocer de los hechos para enfrentarse a las opciones de si \u00a0se \u00a0trataba \u00a0de una conducta punible o de un negocio civil de incumplimiento del \u00a0contrato \u00a0y \u00a0decidirse \u00a0por \u00a0\u00e9sta \u00a0\u00faltima, \u00a0dej\u00f3 desprotegida la buena fe que \u00a0asiste \u00a0a \u00a0los \u00a0ciudadanos \u00a0en \u00a0sus \u00a0transacciones, \u00a0en conclusi\u00f3n que s\u00f3lo se \u00a0explica \u00a0como \u00a0fruto \u00a0de \u00a0una \u00a0desafortunada \u00a0valoraci\u00f3n \u00a0y \u00a0an\u00e1lisis \u00a0de \u00a0los \u00a0elementos probatorios. \u00a0\u00a0<\/p>\n<p>El \u00a0Tribunal \u00a0valor\u00f3 \u00a0mal la naturaleza del \u00a0contrato \u00a0de \u00a0compraventa celebrado entre la denunciante y el procesado, pues si \u00a0bien \u00a0es \u00a0cierto \u00a0que aquella entreg\u00f3 voluntariamente la camioneta, ese acto no \u00a0culminaba \u00a0la \u00a0transacci\u00f3n, \u00a0apenas \u00a0la \u00a0iniciaba, \u00a0de \u00a0modo \u00a0que \u00a0la \u00a0falta de \u00a0cancelaci\u00f3n \u00a0total \u00a0del bien es un enga\u00f1o\u00a0 que \u201cclama por la existencia \u00a0de \u00a0la \u00a0estafa\u201d, \u00a0tal como se ha reconocido jurisprudencialmente en decisiones \u00a0que \u00a0indican \u00a0la \u00a0necesidad \u00a0de obrar de buena fe no s\u00f3lo al contratar, sino al \u00a0cumplir el contrato. \u00a0\u00a0<\/p>\n<p>Finalmente, \u00a0para \u00a0se\u00f1alar la trascendencia \u00a0del \u00a0vicio, \u00a0indica que lo fue por cuanto se afect\u00f3 el patrimonio psicol\u00f3gico, \u00a0moral \u00a0y \u00a0afectivo \u00a0de \u00a0la v\u00edctima porque el sindicado era su cu\u00f1ado y ella lo \u00a0cre\u00eda \u00a0un \u00a0hombre \u00a0leal \u00a0y \u00a0honesto, \u00a0aparte \u00a0que \u00a0la violaci\u00f3n de la norma le \u00a0gener\u00f3 \u00a0un \u00a0sensible \u00a0detrimento de su patrimonio econ\u00f3mico, consecuencias que \u00a0no \u00a0habr\u00edan ocurrido si se \u201chubiera realizado una valoraci\u00f3n en conjunto del \u00a0contrato \u00a0y \u00a0de \u00a0la \u00a0responsabilidad \u00a0del \u00a0comprador \u00a0presunto del veh\u00edculo\u201d, \u00a0razones \u00a0todas \u00a0que \u00a0lo \u00a0conducen \u00a0a \u00a0solicitar que se case la sentencia y en su \u00a0lugar \u00a0se \u00a0confirme \u00a0la \u00a0sentencia condenatoria que dict\u00f3 el Juzgado 10\u00b0 Penal \u00a0del \u00a0 \u00a0Circuito \u00a0 \u00a0de \u00a0 Bogot\u00e1 \u00a0 en \u00a0 contra \u00a0 de \u00a0 RAFAEL \u00a0 GUILLERMO \u00a0 ARENAS \u00a0\u00c1LVAREZ. \u00a0\u00a0<\/p>\n<p>LA CORTE CONSIDERA: \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a01. \u00a0Insistentemente ha se\u00f1alado la Corte \u00a0que \u00a0el \u00a0adecuado \u00a0entendimiento \u00a0de la naturaleza del recurso extraordinario de \u00a0casaci\u00f3n \u00a0es \u00a0imprescindible \u00a0para \u00a0la \u00a0presentaci\u00f3n \u00a0de \u00a0la \u00a0demanda que debe \u00a0demostrar \u00a0de \u00a0manera \u00a0clara \u00a0y precisa los fundamentos de la causal y del cargo \u00a0que \u00a0se \u00a0enuncia \u00a0y \u00a0formula, \u00a0respectivamente, en contra de la sentencia de las \u00a0instancias. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a02. La falta de ese entendimiento genera, \u00a0como \u00a0en este caso, que se sustente esa forma de impugnaci\u00f3n con un escrito que \u00a0prescinde \u00a0de \u00a0todas \u00a0las \u00a0reglas \u00a0de \u00a0la \u00a0t\u00e9cnica que informa la actuaci\u00f3n en \u00a0casaci\u00f3n, \u00a0pasando \u00a0por \u00a0alto \u00a0elementos \u00a0tan \u00a0basilares como la significaci\u00f3n \u00a0extraordinaria \u00a0del \u00a0recurso, \u00a0las \u00a0presunciones \u00a0de \u00a0legalidad y acierto de las \u00a0sentencias \u00a0y \u00a0el \u00a0car\u00e1cter \u00a0asertivo \u00a0de \u00a0los \u00a0errores que se denuncien, entre \u00a0otros. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a03. \u00a0 El \u00a0apoderado \u00a0de \u00a0la \u00a0parte \u00a0civil \u00a0constituida \u00a0dentro \u00a0de \u00a0la \u00a0actuaci\u00f3n \u00a0procesal \u00a0que se adelant\u00f3 en contra de \u00a0RAFAEL \u00a0 GUILLERMO \u00a0ARENAS \u00a0\u00c1LVAREZ \u00a0pretende \u00a0la \u00a0casaci\u00f3n \u00a0de \u00a0la \u00a0sentencia \u00a0absolutoria \u00a0dictada \u00a0por \u00a0el \u00a0Tribunal, \u00a0raz\u00f3n que ubica el recurso dentro del \u00a0\u00e1mbito \u00a0estrictamente \u00a0penal con prescindencia del art\u00edculo 208 del C\u00f3digo de \u00a0Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a04. \u00a0Para \u00a0obtener tal prop\u00f3sito enuncia \u00a0la \u00a0causal \u00a0primera, \u00a0cuerpo segundo, del art\u00edculo 207 del mismo C\u00f3digo,\u00a0 \u00a0precisando \u00a0el cargo dentro de lo que se denomina como error de raciocinio, pues \u00a0reclama \u00a0que \u00a0los \u00a0Juzgadores incurrieron en juicios equivocados al realizar las \u00a0inferencias \u00a0 \u00a0 l\u00f3gicas \u00a0 \u00a0 a \u00a0 \u00a0 partir \u00a0 \u00a0 del \u00a0 \u00a0\u201cempleo \u00a0 \u00a0de \u00a0 \u00a0premisas \u00a0desafortunadas\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0No \u00a0obstante \u00a0ese anuncio, la demanda no aborda la comprobaci\u00f3n de \u00a0lo \u00a0que indica, sino que se queda en esa afirmaci\u00f3n general, sin pasar siquiera \u00a0por \u00a0la \u00a0demostraci\u00f3n \u00a0de \u00a0las \u00a0que \u00a0llama \u201cpremisas desafortunadas\u201d.\u00a0 \u00a0Limitado \u00a0el \u00a0ataque \u00a0de \u00a0forma \u00a0tan rigurosa por el censor, ha debido comprobar \u00a0primero \u00a0cu\u00e1les \u00a0son \u00a0las \u00a0premisas \u00a0del razonamiento l\u00f3gico formal que imputa \u00a0equivocadas \u00a0por \u00a0parte \u00a0del \u00a0Tribunal, \u00a0pues \u00a0si \u00a0se \u00a0refiere \u00a0al entendimiento \u00a0tradicional \u00a0de \u00a0la \u00a0sentencia como un ejercicio silog\u00edstico en el que la norma \u00a0es \u00a0la \u00a0premisa \u00a0mayor, \u00a0los \u00a0hechos \u00a0son \u00a0la premisa menor y la decisi\u00f3n es la \u00a0conclusi\u00f3n, \u00a0la expresi\u00f3n premisas no es \u00fanica, sino m\u00faltiple o por lo menos \u00a0plural. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0O \u00a0si \u00a0dentro \u00a0del \u00a0mismo \u00a0tipo \u00a0de \u00a0razonamiento\u00a0 lo hace con \u00a0referencia \u00a0a \u00a0los \u00a0aspectos puramente probatorios, tiene que demostrar cu\u00e1l es \u00a0la \u00a0premisa \u00a0mayor \u00a0(ley \u00a0de ciencia, principio l\u00f3gico o regla de experiencia), \u00a0cu\u00e1l \u00a0es \u00a0el \u00a0hecho \u00a0(medio \u00a0probatorio) y cu\u00e1l es la conclusi\u00f3n, demostrando \u00a0porqu\u00e9 \u00a0resulta \u00a0equivocada.\u00a0 \u00a0Sin \u00a0embargo \u00a0en \u00a0cada \u00a0uno de esos eventos \u00a0deber\u00e1 \u00a0tener \u00a0en \u00a0cuenta \u00a0la \u00a0existencia \u00a0y \u00a0correcci\u00f3n \u00a0de \u00a0cada \u00a0una de las \u00a0premisas, \u00a0acept\u00e1ndolas \u00a0o \u00a0demostrando \u00a0lo \u00a0contrario, \u00a0pues \u00a0cada \u00a0aspecto en \u00a0particular \u00a0puede \u00a0dar \u00a0origen \u00a0a \u00a0errores propios que tienen sus propias reglas \u00a0l\u00f3gicas de ataque. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0En \u00a0 todo \u00a0caso, \u00a0no \u00a0todos \u00a0los \u00a0razonamientos \u00a0que \u00a0contiene \u00a0una \u00a0sentencia \u00a0son \u00a0necesariamente \u00a0deductivos porque pueden existir algunos de tipo \u00a0inductivo \u00a0y \u00a0otros de clase abductiva, cuyas conclusiones no est\u00e9n sustentadas \u00a0necesariamente \u00a0en la regla que sirve de premisa, sino en la construcci\u00f3n de la \u00a0misma y en la demostraci\u00f3n de su probabilidad. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a05. \u00a0A \u00a0contrario sensu, el demandante se \u00a0limita \u00a0a la transcripci\u00f3n de algunos p\u00e1rrafos de la sentencia, para enseguida \u00a0anotar \u00a0su \u00a0cr\u00edtica \u00a0particular \u00a0indicando \u00a0conclusiones \u00a0diferentes de las del \u00a0Tribunal, \u00a0pero \u00a0sin \u00a0especificar ning\u00fan error concreto en sus razonamientos en \u00a0el \u00a0que \u00a0haya \u00a0podido \u00a0incurrir. \u00a0De \u00a0esa \u00a0manera el escrito queda reducido a un \u00a0alegato \u00a0 de \u00a0 instancia, \u00a0 que \u00a0 no \u00a0 demuestra \u00a0ninguna \u00a0equivocaci\u00f3n \u00a0ni \u00a0su \u00a0trascendencia \u00a0en \u00a0la \u00a0estructuraci\u00f3n \u00a0del fallo que se ataca, que es de lo que \u00a0trata el juicio de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a06. \u00a0 Carga \u00a0 adem\u00e1s \u00a0al \u00a0Tribunal \u00a0una \u00a0supuesta \u00a0equivocaci\u00f3n al valorar el incumplimiento del contrato de compraventa \u00a0como \u00a0un \u00a0asunto puramente civil, por desconocerlo como elemento de una presunta \u00a0actividad \u00a0artificiosa \u00a0y \u00a0enga\u00f1osa \u00a0del \u00a0procesado \u00a0para \u00a0hacerse \u00a0entregar el \u00a0veh\u00edculo \u00a0por \u00a0parte de la v\u00edctima en actividad t\u00edpica de estafa, afirmaci\u00f3n \u00a0perfectamente \u00a0entendible \u00a0del texto de la demanda, pero\u00a0 insuficiente para \u00a0cumplir \u00a0con \u00a0el \u00a0requisito \u00a0formal \u00a0de \u00a0la \u00a0indicaci\u00f3n \u00a0\u201cde \u00a0forma \u00a0clara \u00a0y \u00a0precisa\u201d \u00a0de \u00a0los fundamentos del cargo que exige el art\u00edculo 212 del C\u00f3digo \u00a0de Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Lo \u00a0anterior \u00a0por \u00a0cuanto \u00a0la \u00a0sentencia \u00a0de \u00a0las \u00a0instancias viene \u00a0amparada \u00a0por \u00a0las \u00a0presunciones \u00a0de \u00a0legalidad \u00a0y \u00a0acierto, \u00a0de \u00a0modo que si el \u00a0Tribunal, \u00a0como lo afirma el censor, estim\u00f3 el incumplimiento de un contrato de \u00a0compraventa \u00a0 con \u00a0esa \u00a0precisi\u00f3n \u00a0y \u00a0alcance, \u00a0el \u00a0deber \u00a0del \u00a0censor \u00a0no \u00a0era \u00a0simplemente \u00a0oponerse \u00a0a \u00a0esa \u00a0conclusi\u00f3n, \u00a0sino \u00a0demostrar \u00a0por qu\u00e9 resultaba \u00a0equivocada. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Y \u00a0para \u00a0hacerlo \u00a0ha \u00a0debido \u00a0identificar \u00a0los \u00a0fundamentos \u00a0de esa \u00a0conclusi\u00f3n \u00a0y \u00a0demostrar \u00a0que eran err\u00f3neos, ya fuera como lo anunci\u00f3, \u201cpor \u00a0el \u00a0empleo de premisas desafortunadas\u201d o porque, como tambi\u00e9n lo dice, \u201cpor \u00a0estructurar \u00a0juicios de inferencia no compatibles con la realidad\u201d, pero en un \u00a0caso \u00a0o \u00a0en \u00a0otro \u00a0ha \u00a0debido se\u00f1alar cu\u00e1les eran esas premisas y por qu\u00e9 las \u00a0valoraba \u00a0como \u00a0desafortunadas; \u00a0o \u00a0cu\u00e1l \u00a0era \u00a0la \u00a0inferencia \u00a0y \u00a0por \u00a0qu\u00e9 era \u00a0incompatible \u00a0con \u00a0la \u00a0realidad, \u00a0sin \u00a0olvidar \u00a0que primero deb\u00eda demostrar con \u00a0cu\u00e1l \u00a0realidad, \u00a0pues \u00a0deb\u00eda aclarar si con tal expresi\u00f3n denota la declarada \u00a0en \u00a0el \u00a0proceso \u00a0o \u00a0una \u00a0diferente, caso en el cual deb\u00eda tambi\u00e9n comprobarla, \u00a0nada de lo cual hizo el demandante. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a07.\u00a0 \u00a0 Finalmente, \u00a0 el \u00a0censor \u00a0al \u00a0referirse \u00a0 \u00a0al \u00a0 principio \u00a0 de \u00a0 trascendencia \u00a0 del \u00a0 error \u00a0 demuestra \u00a0 una \u00a0conceptualizaci\u00f3n \u00a0equivocada \u00a0del \u00a0t\u00e9rmino, que\u00a0 en materia de casaci\u00f3n \u00a0no \u00a0hace \u00a0relaci\u00f3n a la incidencia de la vulneraci\u00f3n legal para la v\u00edctima en \u00a0el \u00a0plano \u00a0f\u00e1ctico, \u00a0como lo indica el apoderado al reclamar que se lesion\u00f3 el \u00a0patrimonio \u00a0moral, \u00a0sicol\u00f3gico, \u00a0afectivo y material de su representada, sino a \u00a0la \u00a0importancia \u00a0estructural \u00a0del \u00a0vicio en la construcci\u00f3n de la sentencia, de \u00a0modo \u00a0tal \u00a0que \u00a0s\u00f3lo \u00a0su \u00a0existencia \u00a0la \u00a0sostiene \u00a0por \u00a0lo que se\u00f1al\u00e1ndolo y \u00a0comprob\u00e1ndolo \u00a0 se \u00a0deconstruye \u00a0su \u00a0arquitectura\u00a0 \u00a0haci\u00e9ndose \u00a0necesario \u00a0casarla. \u00a0\u00a0<\/p>\n<p>A \u00a0m\u00e9rito\u00a0 de\u00a0 lo\u00a0 expuesto, \u00a0la \u00a0 \u00a0Corte \u00a0 \u00a0Suprema \u00a0 \u00a0de \u00a0 \u00a0Justicia, \u00a0 Sala \u00a0 de \u00a0 Casaci\u00f3n \u00a0 Penal,\u00a0 \u00a0administrando\u00a0 \u00a0 justicia\u00a0 \u00a0en\u00a0 \u00a0nombre\u00a0 \u00a0de\u00a0 \u00a0la\u00a0 \u00a0Rep\u00fablica y\u00a0 \u00a0\u00a0<\/p>\n<p>por autoridad de la ley, \u00a0<\/p>\n<p>R E S U E L V E \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0INADMITIR \u00a0la \u00a0demanda \u00a0de casaci\u00f3n presentada por el apoderado de \u00a0la \u00a0 parte \u00a0civil \u00a0y, \u00a0en \u00a0consecuencia, \u00a0declarar \u00a0desierto \u00a0el \u00a0recurso.\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Contra la presente decisi\u00f3n no procede recurso alguno \u00a0\u00a0<\/p>\n<p>C\u00daMPLASE \u00a0<\/p>\n<p>YESID RAM\u00cdREZ BASTIDAS \u00a0<\/p>\n<p>FERNANDO \u00a0E. \u00a0ARBOLEDA \u00a0RIPOLL \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0 \u00a0 \u00a0HERMAN \u00a0 GAL\u00c1N \u00a0CASTELLANOS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 A. \u00a0 G\u00c1LVEZ \u00a0 ARGOTE \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JORGE \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0A. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 G\u00d3MEZ \u00a0GALLEGO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00c9DGAR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 LOMBANA \u00a0TRUJILLO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00c1LVARO \u00a0 \u00a0 \u00a0O. \u00a0 \u00a0 P\u00c9REZ \u00a0 \u00a0 PINZ\u00d3N\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>MARINA \u00a0 \u00a0 \u00a0 \u00a0PULIDO \u00a0 \u00a0 \u00a0 \u00a0DE \u00a0BAR\u00d3N\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JORGE\u00a0 L. QUINTERO MILAN\u00c9S \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 19947 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente: \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0Dr. YESID RAM\u00cdREZ BASTIDAS \u00a0\u00a0 Aprobado Acta No. 038 \u00a0 Bogot\u00e1 D.C., veintisiete (27) de marzo de dos \u00a0mil tres\u00a0 (2003). \u00a0\u00a0 V I S [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-7370","post","type-post","status-publish","format-standard","hentry","category-11"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/7370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=7370"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/7370\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=7370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=7370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=7370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}