{"id":6544,"date":"2023-09-08T16:24:36","date_gmt":"2023-09-08T16:24:36","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1921021-05-02\/"},"modified":"2023-09-08T16:24:36","modified_gmt":"2023-09-08T16:24:36","slug":"1921021-05-02","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1921021-05-02\/","title":{"rendered":"19210(21-05-02)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 19210 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACION PENAL \u00a0<\/p>\n<p>Magistrado ponente: \u00a0<\/p>\n<p>Dr. EDGAR LOMBANA TRUJILLO \u00a0<\/p>\n<p>Aprobado Acta No. 54 \u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D.C., \u00a0veintiuno (21) de mayo de dos \u00a0mil dos (2002). \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0Se \u00a0 pronuncia \u00a0 la \u00a0 Sala \u00a0 sobre \u00a0la \u00a0admisibilidad \u00a0de \u00a0la demanda de revisi\u00f3n presentada en defensa del sentenciado \u00a0CARLOS \u00a0HERN\u00c1N MU\u00d1OZ PINEDA \u00a0contra \u00a0el \u00a0fallo \u00a0de \u00a0noviembre \u00a08 \u00a0del \u00a0pasado a\u00f1o, \u00a0mediante \u00a0el cual el Tribunal Superior de Cundinamarca confirm\u00f3 el proferido en \u00a0su \u00a0contra por el Juzgado 2\u00ba Penal del Circuito de Fusagasug\u00e1, conden\u00e1ndolo a \u00a0la \u00a0pena \u00a0principal \u00a0de \u00a0siete \u00a0(7) \u00a0a\u00f1os \u00a0de prisi\u00f3n como autor del delito de \u00a0homicidio \u00a0 en \u00a0 grado \u00a0 de \u00a0tentativa, \u00a0en \u00a0concurso \u00a0con \u00a0hurto \u00a0calificado \u00a0y \u00a0agravado. \u00a0\u00a0<\/p>\n<p>ANTECEDENTES \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01.\u00a0 \u00a0De \u00a0los fallos de instancia se sabe que en la tarde del 23 \u00a0de \u00a0 enero \u00a0de \u00a01988, \u00a0cuando \u00a0Jos\u00e9 \u00a0Didacio \u00a0Benavides \u00a0Espitia \u00a0cabalgaba \u00a0en \u00a0compa\u00f1\u00eda \u00a0de \u00a0su \u00a0hijo Nicanor Benavides Delgado en direcci\u00f3n a su residencia \u00a0ubicada \u00a0en \u00a0la \u00a0verada El Tendido del municipio de Pasca (Cundinamarca), fueron \u00a0atracados \u00a0por dos individuos que les dispararon con armas de fuego.\u00a0 En la \u00a0agresi\u00f3n \u00a0el \u00a0primero \u00a0de \u00a0los citados result\u00f3 herido, en tanto que el segundo \u00a0logr\u00f3 \u00a0evadirse \u00a0no \u00a0sin \u00a0reconocer \u00a0antes \u00a0a \u00a0CARLOS \u00a0HERN\u00c1N \u00a0 \u00a0MU\u00d1OZ \u00a0 \u00a0PINEDA \u00a0 \u00a0como \u00a0 uno \u00a0 de \u00a0 los \u00a0antisociales.\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0Benavides \u00a0 Espitia \u00a0 refiri\u00f3 \u00a0en \u00a0la \u00a0ampliaci\u00f3n \u00a0de \u00a0su denuncia, que a trav\u00e9s de las indagaciones realizadas luego \u00a0de \u00a0los \u00a0sucesos \u00a0estableci\u00f3 \u00a0que \u00a0el \u00a0otro asaltante hab\u00eda sido Sa\u00fal Hort\u00faa \u00a0Morales, \u00a0 e \u00a0 indic\u00f3 \u00a0 haber \u00a0sido \u00a0despojado \u00a0il\u00edcitamente \u00a0de \u00a0la \u00a0suma \u00a0de \u00a0cuatrocientos mil pesos. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02.\u00a0 \u00a0Clausurado \u00a0el ciclo investigativo se calific\u00f3 su m\u00e9rito \u00a0probatorio \u00a0con \u00a0resoluci\u00f3n \u00a0acusatoria de fecha abril 17 de 1997, en la que se \u00a0imput\u00f3 \u00a0 a \u00a0 los \u00a0sindicados \u00a0CARLOS \u00a0HERN\u00c1N \u00a0MU\u00d1OZ \u00a0PINEDA \u00a0y \u00a0Sa\u00fal \u00a0Hort\u00faa \u00a0Morales \u00a0la \u00a0autor\u00eda, \u00a0en \u00a0concurso \u00a0de \u00a0conductas \u00a0punibles, \u00a0de \u00a0los \u00a0delitos \u00a0de \u00a0homicidio \u00a0en grado de \u00a0tentativa y\u00a0 hurto calificado y agravado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a03.\u00a0 \u00a0El \u00a0Juzgado 2\u00ba Penal del Circuito de Fusagasug\u00e1 celebr\u00f3 \u00a0la \u00a0audiencia \u00a0p\u00fablica \u00a0y \u00a0en fallo del 28 de junio de 2001 absolvi\u00f3 a Hort\u00faa \u00a0Morales, \u00a0a \u00a0la \u00a0vez \u00a0que \u00a0conden\u00f3 al procesado MU\u00d1OZ \u00a0PINEDA, \u00a0en \u00a0consonancia con el pliego de cargos, a la \u00a0pena principal de siete (7) a\u00f1os de prisi\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Por \u00a0virtud de la apelaci\u00f3n incoada por el sindicado y su defensor, \u00a0el \u00a0Tribunal \u00a0Superior \u00a0de Cundinamarca revis\u00f3 el pronunciamiento del a quo, al \u00a0que \u00a0le imparti\u00f3 confirmaci\u00f3n integral mediante providencia del 8 de noviembre \u00a0del pasado a\u00f1o. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0El \u00a0demandante \u00a0presenta \u00a0\u201ccomo \u00a0cargo frente a las sentencias de \u00a0primera \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 \u00a0segunda \u00a0 \u00a0 instancia, \u00a0 \u00a0 el \u00a0 \u00a0 de \u00a0 \u00a0 NULIDAD\u201d, \u00a0 que \u00a0invoca \u00a0con \u00a0sustento \u00a0en \u00a0la \u00a0\u201ccausal \u00a0 primera \u00a0 del \u00a0art\u00edculo \u00a0207 \u00a0del \u00a0C\u00f3digo de Procedimiento Penal, Ley 600 de 2000\u201d, \u00a0al \u00a0estimar \u00a0que \u00a0tales \u00a0decisiones \u00a0fueron \u00a0proferidas \u00a0en \u00a0un \u00a0proceso \u00a0inv\u00e1lido \u00a0por encontrarse configurados los \u00a0supuestos \u00a0de \u00a0anulaci\u00f3n previstos en los numerales 2\u00ba y 3\u00ba del art\u00edculo 306 \u00a0ib\u00eddem. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Trat\u00e1ndose \u00a0de \u00a0la \u00a0nulidad \u00a0derivada \u00a0de \u00a0la violaci\u00f3n del debido \u00a0proceso, \u00a0el \u00a0actor \u00a0fundamenta \u00a0dicho \u00a0pedido \u00a0en la irregular notificaci\u00f3n al \u00a0sentenciado \u00a0MU\u00d1OZ PINEDA de \u00a0las \u00a0resoluciones \u00a0proferidas en el curso del proceso y durante el lapso durante \u00a0el \u00a0cual \u00a0permaneci\u00f3 \u00a0en \u00a0contumacia, pues respecto de las mismas se omiti\u00f3 la \u00a0comunicaci\u00f3n \u00a0telegr\u00e1fica otrora ordenada en el art\u00edculo 190 del Decreto 2700 \u00a0de 1991, subrogado por la Ley 81 de 1993. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0punto \u00a0a \u00a0la \u00a0arg\u00fcida \u00a0violaci\u00f3n \u00a0del \u00a0derecho \u00a0de defensa, el \u00a0demandante \u00a0aduce \u00a0que \u00a0su \u00a0asistido \u00a0careci\u00f3 \u00a0en \u00a0forma absoluta de asistencia \u00a0t\u00e9cnica, \u00a0porque \u00a0quienes \u00a0lo representaron en forma oficiosa hasta su captura, \u00a0efectuada \u00a0en \u00a0la \u00a0etapa \u00a0del \u00a0juicio con precedencia a la audiencia p\u00fablica, a \u00a0diferencia \u00a0de \u00a0lo \u00a0afirmado \u00a0por \u00a0el \u00a0Tribunal en el fallo atacado, actuaron de \u00a0manera \u00a0negligente \u00a0y \u00a0descuida \u00a0reflejando el abandono de la gesti\u00f3n confiada. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Con \u00a0 los \u00a0 anteriores \u00a0 argumentos \u00a0 el \u00a0 libelista \u00a0 solicita \u00a0que \u00a0\u201csea \u00a0 \u00a0revisada \u00a0 la \u00a0sentencia, \u00a0declarando \u00a0que \u00a0se ha proferido un juicio viciado, por vulneraci\u00f3n \u00a0del \u00a0derecho \u00a0a \u00a0la \u00a0defensa, \u00a0decretando \u00a0la \u00a0nulidad de lo actuado a partir de \u00a0primer \u00a0 \u00a0 \u00a0 nombramiento \u00a0 \u00a0 \u00a0del \u00a0 \u00a0 \u00a0defensor \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0oficio\u201d. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0demanda \u00a0de revisi\u00f3n con la cual se \u00a0pretende \u00a0remover \u00a0la \u00a0intangibilidad \u00a0de \u00a0una \u00a0decisi\u00f3n \u00a0judicial que ha hecho \u00a0tr\u00e1nsito \u00a0a cosa juzgada, amparada entonces con la doble presunci\u00f3n de acierto \u00a0y \u00a0legalidad, \u00a0seg\u00fan \u00a0el \u00a0reiterado \u00a0y pac\u00edfico criterio de la Sala, en manera \u00a0alguna \u00a0constituye un escrito de libre elaboraci\u00f3n; por el contrario, en virtud \u00a0del \u00a0mandato expreso del legislador ha de satisfacer las exigencias establecidas \u00a0en \u00a0el \u00a0art\u00edculo \u00a0222 \u00a0del C\u00f3digo de Procedimiento Penal y acompa\u00f1arse de los \u00a0documentos \u00a0igualmente \u00a0se\u00f1alados \u00a0en \u00a0ese \u00a0mismo \u00a0precepto, \u00a0de \u00a0manera que la \u00a0ausencia \u00a0de \u00a0dichos \u00a0requisitos \u00a0formales determina su inadmisi\u00f3n al tenor del \u00a0art\u00edculo \u00a0223 \u00a0ib\u00eddem, como se anuncia\u00a0 respecto del libelo presentado en \u00a0defensa del sentenciado MU\u00d1OZ PINEDA. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01.\u00a0 \u00a0En \u00a0efecto, por disposici\u00f3n del art\u00edculo 220 ejusdem, la \u00a0acci\u00f3n \u00a0de revisi\u00f3n s\u00f3lo procede contra decisiones ejecutoriadas, tr\u00e1tese de \u00a0sentencias, \u00a0resoluciones \u00a0de \u00a0preclusi\u00f3n \u00a0de \u00a0la \u00a0investigaci\u00f3n o de autos de \u00a0cesaci\u00f3n \u00a0de \u00a0procedimiento, \u00a0seg\u00fan el caso, circunstancia que ineludiblemente \u00a0le \u00a0corresponde \u00a0demostrar \u00a0al \u00a0actor, \u00a0quien \u00a0para \u00a0este \u00a0espec\u00edfico \u00a0fin y en \u00a0acatamiento \u00a0del inciso final del precitado art\u00edculo 222 de la Ley 600 de 2000, \u00a0debe \u00a0anexar \u00a0la \u00a0copia \u00a0o \u00a0fotocopia \u00a0de \u00a0las \u00a0decisiones \u00a0de primera y segunda \u00a0instancia \u00a0con \u00a0la \u00a0constancia \u00a0de \u00a0su ejecutoria, documento este \u00faltimo que no \u00a0sobra \u00a0agregar, \u00a0le \u00a0compete \u00a0expedir a la autoridad judicial respectiva como lo \u00a0precept\u00faa el art\u00edculo 116 del C\u00f3digo de Procedimiento Civil. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0la \u00a0demanda \u00a0examinada \u00a0el \u00a0apoderado \u00a0incorpor\u00f3 \u00a0tan s\u00f3lo las \u00a0fotocopias \u00a0de \u00a0los \u00a0fallos \u00a0dictados \u00a0por \u00a0el Juzgado 2\u00ba Penal del Circuito de \u00a0Fusagasuga \u00a0 y \u00a0 el \u00a0 Tribunal \u00a0 Superior \u00a0de \u00a0Cundinamarca; \u00a0sin \u00a0embargo, \u00a0con \u00a0posterioridad \u00a0y \u00a0encontr\u00e1ndose \u00a0la \u00a0solicitud en esta Corporaci\u00f3n, alleg\u00f3 la \u00a0constancia \u00a0sobre \u00a0la \u00a0firmeza \u00a0del pronunciamiento cuya revisi\u00f3n pretende, que \u00a0por \u00a0la \u00a0raz\u00f3n \u00a0acotada en precedencia surg\u00eda imprescindible para discernir si \u00a0la acci\u00f3n promovida resultaba o no viable atendida su ejecutoria. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02.\u00a0 \u00a0Pero \u00a0si la deficiencia as\u00ed advertida fue subsanada antes \u00a0del \u00a0pronunciamiento \u00a0de \u00a0la \u00a0Sala, \u00a0igual \u00a0no \u00a0acontece \u00a0al \u00a0pasar \u00a0por alto el \u00a0demandante \u00a0que \u00a0la \u00a0revisi\u00f3n \u00fanicamente procede por los motivos taxativamente \u00a0se\u00f1alados \u00a0en \u00a0el \u00a0art\u00edculo \u00a0220 \u00a0del C\u00f3digo de Procedimiento Penal, no en el \u00a0art\u00edculo \u00a0207 \u00a0ejusdem como lo entiende de manera equivocada, pues esta \u00faltima \u00a0norma \u00a0alude a los supuestos en los cuales es posible acudir en casaci\u00f3n, medio \u00a0de \u00a0impugnaci\u00f3n que a pesar de ostentar tambi\u00e9n un car\u00e1cter extraordinario se \u00a0inspira \u00a0en \u00a0fines \u00a0totalmente \u00a0diversos \u00a0de \u00a0aquella, a la vez que su ejercicio \u00a0corresponde \u00a0a \u00a0un \u00a0tr\u00e1mite, \u00a0a \u00a0oportunidades \u00a0y \u00a0exigencias diferentes.\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Esta \u00a0desatinada \u00a0comprensi\u00f3n \u00a0del \u00a0actor \u00a0lo condujo a plantear la \u00a0revisi\u00f3n \u00a0del \u00a0fallo \u00a0de segunda instancia con cimiento en la configuraci\u00f3n de \u00a0presuntos \u00a0errores \u00a0de \u00a0procedimiento \u00a0a \u00a0los \u00a0que les asigna trascendencia para \u00a0propiciar \u00a0la \u00a0nulidad \u00a0de \u00a0lo actuado, perdiendo de vista que de haber existido \u00a0debieron \u00a0 ser \u00a0planteados \u00a0en \u00a0tiempo \u00a0dentro \u00a0del \u00a0recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n, \u00a0 desde \u00a0 luego, \u00a0mediante \u00a0la \u00a0demanda \u00a0respectiva \u00a0ajustada \u00a0a \u00a0los \u00a0requisitos \u00a0formales \u00a0establecidos \u00a0legalmente para la misma, no a trav\u00e9s de la \u00a0acci\u00f3n \u00a0impetrada, \u00a0concebida \u00a0para \u00a0remover la firmeza de una decisi\u00f3n que se \u00a0muestra ostensiblemente injusta. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0s\u00edntesis, \u00a0la demanda en el caso de autos no aparece apoyada en \u00a0alguna \u00a0de \u00a0las \u00a0causales \u00a0por \u00a0raz\u00f3n \u00a0de \u00a0las \u00a0cuales \u00a0al \u00a0tenor del art\u00edculo \u00a0220\u00a0 \u00a0del \u00a0estatuto instrumental penal surge viable la revisi\u00f3n contra las \u00a0sentencias \u00a0ejecutoriadas; \u00a0menos \u00a0a\u00fan, \u00a0se \u00a0expresaron \u00a0por \u00a0el \u00a0apoderado los \u00a0fundamentos \u00a0de \u00a0hecho \u00a0y \u00a0de \u00a0derecho \u00a0que \u00a0soportan la solicitud de revisi\u00f3n, \u00a0ofreci\u00e9ndose entonces por completo infundada. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0As\u00ed \u00a0las \u00a0cosas, con asidero en art\u00edculo 223 de la Ley 600 de 2000 \u00a0la \u00a0Corte \u00a0inadmitir\u00e1 \u00a0la \u00a0demanda \u00a0de \u00a0revisi\u00f3n \u00a0presentada \u00a0en \u00a0defensa \u00a0del \u00a0sentenciado CARLOS HERN\u00c1N MU\u00d1OZ PINEDA. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Contra esta decisi\u00f3n procede el recurso \u00a0de reposici\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0raz\u00f3n \u00a0y \u00a0m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, \u00a0Sala de Casaci\u00f3n Penal, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01.\u00a0 Reconocer al Dr. Tito Guti\u00e9rrez \u00a0Cabrera \u00a0como \u00a0defensor \u00a0del \u00a0condenado \u00a0CARLOS HERN\u00c1N \u00a0MU\u00d1OZ \u00a0PINEDA en los t\u00e9rminos y para los efectos del \u00a0poder conferido por su representado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0INADMITIR \u00a0la \u00a0demanda \u00a0de \u00a0revisi\u00f3n \u00a0presentada \u00a0en \u00a0nombre del sentenciado \u00a0CARLOS HERN\u00c1N MU\u00d1OZ PINEDA, \u00a0conforme \u00a0a las motivaciones consignadas en la parte motiva de esta providencia. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Notif\u00edquese y c\u00famplase. \u00a0\u00a0<\/p>\n<p>\u00c1LVARO ORLANDO P\u00c9REZ PINZ\u00d3N \u00a0<\/p>\n<p>FERNANDO \u00a0E. \u00a0ARBOLEDA \u00a0RIPOLL \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 JORGE E. C\u00d3RDOBA POVEDA \u00a0\u00a0<\/p>\n<p>HERMAN \u00a0 GALAN \u00a0 CASTELLANOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 CARLOS A. G\u00c1LVEZ ARGOTE \u00a0\u00a0<\/p>\n<p>JORGE \u00a0 A. \u00a0 G\u00d3MEZ \u00a0 GALLEGO\u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 EDGAR LOMBANA TRUJILLO \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 E. \u00a0 MEJ\u00cdA \u00a0 ESCOBAR \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0NILSON PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 19210 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACION PENAL \u00a0 Magistrado ponente: \u00a0 Dr. EDGAR LOMBANA TRUJILLO \u00a0 Aprobado Acta No. 54 \u00a0 Bogot\u00e1 \u00a0D.C., \u00a0veintiuno (21) de mayo de dos \u00a0mil dos (2002). \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0Se \u00a0 pronuncia \u00a0 la \u00a0 Sala \u00a0 sobre \u00a0la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-6544","post","type-post","status-publish","format-standard","hentry","category-10"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/6544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=6544"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/6544\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=6544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=6544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=6544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}