{"id":6493,"date":"2023-09-08T16:24:32","date_gmt":"2023-09-08T16:24:32","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1912805-02-02\/"},"modified":"2023-09-08T16:24:32","modified_gmt":"2023-09-08T16:24:32","slug":"1912805-02-02","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1912805-02-02\/","title":{"rendered":"19128(05-02-02)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 19128 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrado \u00a0Ponente \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 \u00a0Dr. \u00a0JORGE \u00a0ANIBAL \u00a0GOMEZ \u00a0GALLEGO \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Aprobado Acta No. 10 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Bogot\u00e1 D. C., cinco de febrero de dos mil dos. \u00a0\u00a0<\/p>\n<p>V I S T O S \u00a0<\/p>\n<p>Resuelve \u00a0la \u00a0Corte \u00a0la colisi\u00f3n negativa de \u00a0competencias \u00a0surgida \u00a0entre \u00a0el Juzgado 2\u00b0 Penal del Circuito Especializado de \u00a0Medell\u00edn \u00a0y \u00a0el \u00a0Juzgado \u00a02\u00ba\u00a0 \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Bello, \u00a0para \u00a0el \u00a0conocimiento \u00a0de \u00a0la \u00a0causa \u00a0adelantada contra EDGARDO \u00a0ECHEVERRIA \u00a0PORRAS y JOSE MANUEL ALBARRACIN PINEDA, por \u00a0el delito de hurto calificado y agravado. \u00a0\u00a0<\/p>\n<p>ANTECEDENTES \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01. \u00a0El \u00a015 \u00a0de \u00a0marzo \u00a0de \u00a02001, unidades adscritas a la Polic\u00eda de \u00a0Carreteras \u00a0que patrullaban por inmediaciones de la autopista Medell\u00edn Bogot\u00e1, \u00a0en \u00a0 el \u00a0 sitio \u00a0 conocido \u00a0como \u00a0la \u00a0\u201cCurva \u00a0 \u00a0 de \u00a0 \u00a0 Rodas\u201d \u00a0en \u00a0el \u00a0municipio \u00a0de \u00a0Bello, \u00a0inmovilizaron \u00a0una \u00a0tractomula tipo \u00a0carrotanque, \u00a0Chevrolet Brigadier, de placas FTH 771, conducida por JOSE \u00a0 \u00a0MANUEL \u00a0 ALBARRACIN \u00a0 PINEDA \u00a0 y \u00a0conteniendo \u00a0 9.000 \u00a0 galones \u00a0de \u00a0combustible \u00a0que \u00a0conforme \u00a0a \u00a0documentaci\u00f3n \u00a0presentada \u00a0por \u00a0el \u00a0conductor \u00a0ten\u00eda \u00a0como \u00a0destino \u00a0la \u00a0planta \u00a0de la empresa \u00a0Vestimundo con sede en el municipio de Marinilla. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a0lugar de destino despert\u00f3 sospecha en los uniformados porque si \u00a0deb\u00eda \u00a0descargar \u00a0en ese municipio no se entend\u00eda porqu\u00e9 transitaba ya en las \u00a0goteras \u00a0de \u00a0Medell\u00edn, \u00a0raz\u00f3n \u00a0por \u00a0la \u00a0cual contactaron telef\u00f3nicamente a la \u00a0empresa \u00a0Vestimundo, \u00a0quienes expresaron desconocer por completo esa remisi\u00f3n y \u00a0no tener previsto el recibo de pedidos. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Ante \u00a0lo \u00a0confuso \u00a0de \u00a0la \u00a0situaci\u00f3n \u00a0las \u00a0autoridades \u00a0optaron por \u00a0contactar \u00a0personal \u00a0de \u00a0Ecopetrol \u00a0y \u00a0uno de sus t\u00e9cnicos hizo presencia en el \u00a0lugar \u00a0efectuando \u00a0un examen preliminar al combustible se\u00f1alando que se trataba \u00a0de petr\u00f3leo crudo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02. \u00a0Por \u00a0los anteriores hechos, un Fiscal Especializado de Medell\u00edn \u00a0mediante \u00a0decisi\u00f3n \u00a0fechada \u00a0el 23 de octubre de 2001, profiri\u00f3 resoluci\u00f3n de \u00a0acusaci\u00f3n \u00a0contra \u00a0EDGARDO \u00a0ECHEVERRIA PORRAS y JOSE \u00a0MANUEL \u00a0 \u00a0 ALBARRACIN \u00a0 \u00a0PINEDA, \u00a0 \u00a0\u201cpor \u00a0el \u00a0delito \u00a0de HURTO AGRAVADO Y CALIFICADO sobre combustible de \u00a0una \u00a0entidad \u00a0estatal \u00a0como \u00a0lo \u00a0es \u00a0Ecopetrol, acorde a los art\u00edculos 349, 350 \u00a0numeral \u00a01\u00ba, \u00a0351 \u00a0numerales 7 y 9 y 372 del anterior c\u00f3digo penal\u201d, \u00a0normatividad \u00a0favorable frente a la \u00a0penalidad \u00a0consagrada \u00a0en \u00a0los \u00a0art\u00edculo \u00a0239, \u00a0240 \u00a0y 241 numeral 14 del nuevo \u00a0C\u00f3digo penal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a03. \u00a0Ejecutoriada la acusaci\u00f3n, el proceso \u00a0correspondi\u00f3 \u00a0al Juzgado Segundo Penal del Circuito Especializado de Medell\u00edn, \u00a0despacho \u00a0que \u00a0en providencia de diciembre 11 de 2000 se abstiene de conocer del \u00a0proceso con base en los siguientes argumentos: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0 la \u00a0 acusaci\u00f3n \u00a0 se \u00a0 afirma \u00a0 que \u00a0 se \u00a0 est\u00e1 \u00a0 \u201cante \u00a0 un \u00a0 hurto \u00a0 de \u00a0 combustible \u00a0propiedad \u00a0de \u00a0Ecopetrol, \u00a0empresa industrial y comercial del Estado\u201d y se hace alusi\u00f3n al decreto 300 del \u00a015 \u00a0de \u00a0febrero \u00a0de \u00a01993 \u00a0del Ministerio de Minas y Energ\u00eda, diciendo que para \u00a0\u201csaber \u00a0si \u00a0el \u00a0producto \u00a0viene \u00a0de oleoducto, poliducto o gasoducto, la Empresa Colombiana de Petr\u00f3leos, \u00a0aplica \u00a0un reactivo qu\u00edmico a los combustibles entregados a los mayoristas para \u00a0luego \u00a0 \u00a0ser \u00a0 \u00a0depositados \u00a0 \u00a0en \u00a0 \u00a0los \u00a0 \u00a0tanques \u00a0 \u00a0de \u00a0 \u00a0las \u00a0 \u00a0\u2018bombas \u00a0 \u00a0de \u00a0 servicio\u2019\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Pero \u00a0estas afirmaciones, agrega, no demuestran por s\u00ed solas que el \u00a0hurto \u00a0del crudo haya sido sustra\u00eddo de un oleoducto, pues, el se\u00f1or Fiscal al \u00a0hacer \u00a0el \u00a0respectivo \u00a0an\u00e1lisis \u00a0con \u00a0base \u00a0en \u00a0el \u00a0citado decreto, emanado del \u00a0Ministerio \u00a0de \u00a0Minas \u00a0y \u00a0Energ\u00eda, concluye que si el combustible no muestra la \u00a0marca \u00a0 suministrada \u00a0 por \u00a0 Ecopetrol, \u00a0 necesariamente \u00a0fue \u00a0obtenido \u00a0de \u00a0sus \u00a0viaductos. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Pero \u00a0la \u00a0marca \u00a0que \u00a0Ecopetrol \u00a0hace a su producto, no puede ser la \u00a0raz\u00f3n \u00a0 determinante \u00a0para \u00a0concluir \u00a0que \u00a0el \u00a0producto \u00a0fue \u00a0extra\u00eddo \u00a0de \u00a0un \u00a0oleoducto, \u00a0por \u00a0cuanto tal como lo se\u00f1al\u00f3 esta Corporaci\u00f3n en la providencia \u00a0de \u00a0mayo \u00a018 \u00a0de 1998 en la cual se afirma que no es Ecopetrol la \u00fanica empresa \u00a0que en nuestro pa\u00eds explota petr\u00f3leo y produce sus derivados. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Agrega \u00a0 \u00a0 \u00a0 que \u00a0 \u00a0 \u00a0\u201cas\u00ed \u00a0como \u00a0deduce \u00a0el \u00a0Fiscal que dicho crudo fue sustra\u00eddo de un \u00a0poliducto, \u00a0nada \u00a0impide \u00a0al \u00a0despacho, \u00a0por \u00a0no \u00a0existir \u00a0prueba \u00a0en contrario, \u00a0conjeturar \u00a0 que \u00a0 haya \u00a0 sido \u00a0 sacado \u00a0 de \u00a0un \u00a0centro \u00a0de \u00a0acopio\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Concluye \u00a0entonces \u00a0que \u00a0al \u00a0no \u00a0estar \u00a0plenamente acreditado que el \u00a0petr\u00f3leo \u00a0se sustrajo de un oleoducto \u201co \u00a0 \u00a0 \u00a0fuentes \u00a0 \u00a0 \u00a0inmediatas \u00a0 \u00a0 de \u00a0 \u00a0 abastecimiento\u201d, \u00a0la competencia debe ser radicada en \u00a0los \u00a0juzgados \u00a0penales \u00a0del \u00a0circuito, \u00a0a donde env\u00eda el expediente \u00a0 proponiendo \u00a0 colisi\u00f3n \u00a0negativa \u00a0de \u00a0competencias. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a04. \u00a0 El \u00a0 Juzgado \u00a0 2\u00ba \u00a0 Penal \u00a0 del \u00a0Circuito \u00a0de \u00a0Bello \u00a0a \u00a0quien \u00a0correspondiera \u00a0el \u00a0conocimiento \u00a0del caso, mediante providencia de enero 21 del \u00a0a\u00f1o \u00a0en \u00a0curso se abstiene de avocar el conocimiento del mismo, argumentando en \u00a0esencia lo siguiente: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0No \u00a0es \u00a0la \u00a0calidad \u00a0del \u00a0afectado con el hurto la circunstancia que \u00a0fija \u00a0la \u00a0competencia \u00a0en \u00a0estos \u00a0casos, sino el hecho de que el petr\u00f3leo o sus \u00a0derivados \u00a0sean \u00a0sustra\u00eddos \u00a0de \u00a0un \u00a0oleoducto, \u00a0gasoducto, poliducto o fuentes \u00a0inmediatas \u00a0de abastecimiento, tal como lo establece ahora de manera espec\u00edfica \u00a0el \u00a0numeral \u00a014 \u00a0del \u00a0art\u00edculo \u00a0241 \u00a0en \u00a0concordancia \u00a0con \u00a0el \u00a0art\u00edculo \u00a05-13 \u00a0transitorio del nuevo C\u00f3digo Penal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Resulta \u00a0claro para el Juzgado entender que todo petr\u00f3leo crudo que \u00a0se \u00a0extrae \u00a0en el pa\u00eds es de propiedad de Ecopetrol, y que es cosa distinta que \u00a0esta \u00a0empresa \u00a0industrial \u00a0y \u00a0comercial \u00a0del \u00a0Estado \u00a0celebre \u00a0convenios para la \u00a0exploraci\u00f3n \u00a0y \u00a0explotaci\u00f3n \u00a0del \u00a0crudo. \u00a0Asimismo, que todos los oleoductos y \u00a0poliductos son de su propiedad. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0el \u00a0presente \u00a0caso, \u00a0el combustible o hidrocarburo crudo que fue \u00a0decomisado \u00a0al \u00a0procesado \u00a0detenido, \u00a0hab\u00eda \u00a0sido \u00a0sustra\u00eddo de un oleoducto y \u00a0jam\u00e1s \u00a0hab\u00eda sido comercializado por Ecopetrol o cualquiera de las compa\u00f1\u00edas \u00a0concesionarias, \u00a0pues \u00a0como \u00a0se \u00a0ha \u00a0repetido \u00a0a \u00a0lo largo del averiguatorio, no \u00a0ten\u00eda \u00a0el \u00a0reactivo qu\u00edmico que se utiliza para conocer si el producto ha sido \u00a0o no comercializado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0De \u00a0all\u00ed \u00a0que, \u00a0tal como lo asevera el se\u00f1or MARCO ANTONIO ALARCON \u00a0CASTRO \u00a0en \u00a0su \u00a0declaraci\u00f3n \u00a0obrante a folios 41 y 42 del cuaderno original, el \u00a0crudo \u00a0decomisado \u00a0debi\u00f3 \u00a0ser \u00a0hurtado de uno de los oleoductos que transportan \u00a0crudo \u00a0entre \u00a0la \u00a0estaci\u00f3n \u00a0Vasconia \u00a0(Puerto Boyac\u00e1) y Cove\u00f1as, es decir del \u00a0oleoducto \u00a0que maneja OCCENSA o del oleoducto Colombia, operado directamente por \u00a0Ecopetrol. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Concluye \u00a0entonces \u00a0que \u00a0la \u00a0competencia \u00a0para \u00a0el \u00a0conocimiento del \u00a0asunto \u00a0le \u00a0corresponde a los jueces penales del circuito especializados, raz\u00f3n \u00a0por \u00a0la \u00a0cual \u00a0acepta la colisi\u00f3n propuesta y ordena la remisi\u00f3n del proceso a \u00a0esta Corporaci\u00f3n. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Aunque \u00a0la \u00a0colisi\u00f3n \u00a0negativa de competencias se suscit\u00f3 entre el \u00a0Juzgado \u00a0Segundo \u00a0Penal \u00a0del \u00a0Circuito \u00a0Especializado \u00a0de Medell\u00edn y el Juzgado \u00a0Segundo \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Bello, ambos pertenecientes al mismo Distrito \u00a0Judicial, \u00a0resulta claro que corresponde a esta colegiatura resolverlo, teniendo \u00a0en \u00a0cuenta \u00a0lo \u00a0dispuesto en inciso 2\u00b0 del art\u00edculo 18 transitorio del C\u00f3digo \u00a0de Procedimiento Penal (Ley 600 de 2000). \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a0numeral \u00a013 del art\u00edculo 5\u00ba transitorio de la ley 600 de 2000, \u00a0radica \u00a0 en \u00a0cabeza \u00a0de \u00a0los \u00a0jueces \u00a0penales \u00a0del \u00a0circuito \u00a0especializados \u00a0el \u00a0conocimiento \u00a0del \u00a0\u201churto \u00a0agravado \u00a0seg\u00fan \u00a0el \u00a0art\u00edculo \u00a0241 \u00a0numeral \u00a014 \u00a0del C\u00f3digo Penal\u201d \u00a0 \u00a0 . \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0referida \u00a0circunstancia \u00a0de \u00a0agravaci\u00f3n \u00a0del hurto se configura \u00a0cuando \u00a0 \u00a0aquel \u00a0 \u00a0recae \u00a0 \u00a0sobre \u00a0 \u00a0\u201cpetr\u00f3leo \u00a0o \u00a0sus \u00a0derivados \u00a0cuando se sustraigan de un oleoducto, \u00a0gasoducto, \u00a0 \u00a0 \u00a0 \u00a0poliducto \u00a0 \u00a0 \u00a0 \u00a0o \u00a0 \u00a0 \u00a0 \u00a0fuentes \u00a0 \u00a0 \u00a0 inmediatas\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Por \u00a0tanto \u00a0cuando el hurto tenga por objeto material el petr\u00f3leo o \u00a0sus \u00a0derivados \u00a0y \u00a0haya sido sustra\u00eddo de oleoducto, gasoducto o de sus fuentes \u00a0inmediatas \u00a0de abastecimiento la competencia para conocer de \u00e9ste y sus conexos \u00a0ser\u00e1 \u00a0del \u00a0juez \u00a0especializado. \u00a0En \u00a0sentido \u00a0contrario, \u00a0cuando \u00a0no \u00a0se logren \u00a0determinar \u00a0esas \u00a0circunstancias \u00a0operar\u00e1 \u00a0entonces \u00a0la \u00a0cl\u00e1usula \u00a0general \u00a0de \u00a0competencia \u00a0que \u00a0corresponde \u00a0al \u00a0juez \u00a0del \u00a0circuito o, mirada la cuant\u00eda, en \u00a0tanto \u00a0 sea \u00a0inferior \u00a0a \u00a050 \u00a0salarios \u00a0m\u00ednimos, \u00a0se \u00a0trasladar\u00e1 \u00a0entonces \u00a0la \u00a0competencia al juzgado penal municipal. \u00a0\u00a0<\/p>\n<p>Los juzgados en conflicto no ponen en tela de \u00a0juicio \u00a0la \u00a0calificaci\u00f3n por el punible de hurto en los t\u00e9rminos especificados \u00a0en \u00a0la \u00a0resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n \u00a0y \u00a0tampoco \u00a0hay \u00a0discrepancia por supuesto, \u00a0alrededor \u00a0 del \u00a0 objeto \u00a0 material \u00a0 de \u00a0 la \u00a0conducta \u00a0-petr\u00f3leo \u00a0crudo-. \u00a0La \u00a0contradicci\u00f3n \u00a0surge \u00a0al momento de analizar los factores de competencia que se \u00a0pretenden \u00a0para \u00a0el \u00a0hecho \u00a0objeto \u00a0del \u00a0proceso, \u00a0la \u00a0cual gira alrededor de la \u00a0determinaci\u00f3n \u00a0de \u00a0una \u00a0circunstancia \u00a0espacial, \u00a0pues \u00a0mientras el Juzgado del \u00a0Circuito \u00a0infiere \u00a0que \u00a0el hurto se cometi\u00f3 en el oleoducto y que jam\u00e1s hab\u00eda \u00a0sido \u00a0comercializado \u00a0por \u00a0Ecopetrol, el Juzgado Especializado argumenta que tal \u00a0hecho no se encuentra demostrado. \u00a0\u00a0<\/p>\n<p>Para \u00a0resolver \u00a0el \u00a0punto, considera la Sala \u00a0necesario \u00a0 recordar \u00a0que \u00a0la \u00a0resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n, \u00a0proferida \u00a0con \u00a0las \u00a0formalidades \u00a0legales, \u00a0es \u00a0la \u00a0pieza \u00a0procesal \u00a0que \u00a0se\u00f1ala el marco jur\u00eddico \u00a0dentro \u00a0del \u00a0cual \u00a0debe \u00a0desenvolverse \u00a0el \u00a0juicio \u00a0y la sentencia, toda vez que \u00a0informa \u00a0las circunstancias de tiempo, modo y lugar en que sucedieron los hechos \u00a0y \u00a0la \u00a0calificaci\u00f3n \u00a0jur\u00eddica provisional dada a los mismos, la que, a su vez, \u00a0determina \u00a0la \u00a0competencia \u00a0del \u00a0juez, \u00a0y \u00a0tiene \u00a0con \u00a0relaci\u00f3n \u00a0a \u00a0\u00e9l \u00a0fuerza \u00a0vinculante, \u00a0no pudiendo desconocerla, a menos que se haya incurrido en error en \u00a0la denominaci\u00f3n jur\u00eddica de la infracci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Por lo tanto, la discusi\u00f3n incidental que \u00a0se \u00a0 promueva \u00a0 en \u00a0 torno \u00a0a \u00a0la \u00a0competencia \u00a0del \u00a0juez \u00a0para \u00a0conocer \u00a0de \u00a0un \u00a0determinado\u00a0 \u00a0 proceso, \u00a0 debe \u00a0 estar \u00a0 referida \u00a0 a \u00a0 las \u00a0circunstancias \u00a0determinadas en la acusaci\u00f3n. \u00a0\u00a0<\/p>\n<p>En \u00a0el \u00a0presente \u00a0caso, \u00a0el \u00a0punto que ahora \u00a0genera \u00a0discusi\u00f3n \u00a0fue \u00a0discutido \u00a0en el curso del proceso y por supuesto en la \u00a0resoluci\u00f3n \u00a0de acusaci\u00f3n de cuya lectura integral se deduce que la competencia \u00a0se \u00a0determin\u00f3 por la circunstancia del numeral 14 del art\u00edculo 5\u00ba transitorio \u00a0en cabeza de los jueces especializados. \u00a0\u00a0<\/p>\n<p>As\u00ed, en la decisi\u00f3n fechada el 17 de mayo \u00a0de \u00a02001 \u00a0por \u00a0medio \u00a0de la cual un Fiscal Delegado ante el Tribunal Superior de \u00a0Medell\u00edn \u00a0confirm\u00f3 \u00a0la \u00a0resoluci\u00f3n \u00a0que \u00a0neg\u00f3 al revocatoria de la medida de \u00a0aseguramiento \u00a0impuesta \u00a0al \u00a0procesado \u00a0JOSE \u00a0MANUEL \u00a0ALBARRACIN PINEDA, se dijo \u00a0alrededor de la prueba para establecer la competencia, que: \u00a0\u00a0<\/p>\n<p>\u201cResulta v\u00e1lido \u00a0puntualizar \u00a0que \u00a0el \u00a0hurto \u00a0de \u00a0petr\u00f3leo \u00a0y \u00a0sus \u00a0derivados \u00a0causa \u00a0un inmenso \u00a0perjuicio \u00a0al \u00a0Sistema \u00a0Nacional \u00a0de \u00a0Combustibles, \u00a0adem\u00e1s \u00a0es \u00a0claro \u00a0que \u00a0el \u00a0veh\u00edculo \u00a0en \u00a0el \u00a0cual se transportaba el crudo decomisado ven\u00eda procedente de \u00a0las \u00a0inmediaciones \u00a0de \u00a0la \u00a0localidad de Vasconia del Magdalena Medio, lugar por \u00a0donde \u00a0est\u00e1n \u00a0extendidas las redes del oleoducto CA\u00d1O LIMON-COVE\u00d1AS el que de \u00a0manera \u00a0reiterada \u00a0es \u00a0objeto \u00a0de \u00a0perforaciones fraudulentas con el consecuente \u00a0hurto \u00a0del \u00a0crudo \u00a0que \u00a0se \u00a0conduce \u00a0por \u00a0ese \u00a0medio, lo cual le ocasiona graves \u00a0consecuencias \u00a0a la econom\u00eda nacional por la disminuci\u00f3n del abastecimiento, a \u00a0las \u00a0que hay que sumar los peligros de tragedias de incalculables consecuencias, \u00a0para \u00a0la \u00a0vida \u00a0humana, al ecosistema y a la riqueza agr\u00edcola y agropecuaria de \u00a0la naci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u201cEn \u00a0 esa \u00a0direcci\u00f3n \u00a0tuvo \u00a0a \u00a0bien \u00a0el \u00a0legislador atribuir competencia para investigar y \u00a0juzgar \u00a0estos \u00a0delitos \u00a0en \u00a0jurisdicciones \u00a0especiales, como se desprende de las \u00a0normas \u00a0 contenidas \u00a0 en \u00a0 la \u00a0 Ley \u00a0 418\/97 \u00a0 y \u00a0 de \u00a0la \u00a0de \u00a0hoy \u00a0vigente \u00a0Ley \u00a0504\/99\u201d \u00a0(fls. \u00a0149 \u00a0y \u00a0150). \u00a0\u00a0<\/p>\n<p>En \u00a0la resoluci\u00f3n acusatoria se empieza por \u00a0reafirmar \u00a0 \u00a0 esa \u00a0 \u00a0competencia \u00a0 \u00a0cuando \u00a0 \u00a0se \u00a0 \u00a0dice \u00a0 \u00a0que: \u00a0 \u00a0\u201cDesde \u00a0el momento mismo de definir la \u00a0situaci\u00f3n \u00a0jur\u00eddica \u00a0aclaramos \u00a0nuestra \u00a0competencia \u00a0frente \u00a0a \u00a0\u00e9ste asunto, \u00a0referido \u00a0a \u00a0\u00e9ste tipo de delitos tanto en el anterior C\u00f3digo como conforme al \u00a0nuevo \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0seg\u00fan \u00a0el art\u00edculo 5\u00ba transitorio, \u00a0numeral \u00a014\u201d, descartando \u00a0m\u00e1s \u00a0 adelante \u00a0 los \u00a0 argumentos \u00a0del \u00a0Ministerio \u00a0P\u00fablico \u00a0alrededor \u00a0de \u00a0la \u00a0inexistencia \u00a0de \u00a0prueba que determinase que el petr\u00f3leo hab\u00eda sido sustra\u00eddo \u00a0de un oleoducto, con base en los siguientes razonamientos: \u00a0\u00a0<\/p>\n<p>\u201cEn efecto, el \u00a0decreto \u00a0300 \u00a0del 15 de febrero de 1993 (f. 43), emanado del Ministerio de Minas \u00a0y \u00a0Energ\u00eda, \u00a0se\u00f1ala los requisitos que deben tener las facturas para cuando se \u00a0va \u00a0a transportar combustibles y para efectos de reconocer a estos, o sea, saber \u00a0si \u00a0el producto viene de oleoducto, poliducto o gasoducto, la Empresa Colombiana \u00a0de \u00a0Petr\u00f3leos, \u00a0aplica un reactivo qu\u00edmico a los combustibles entregados a los \u00a0mayoristas \u00a0para \u00a0luego \u00a0ser \u00a0depositados \u00a0en \u00a0los \u00a0tanques \u00a0de las \u201cbombas \u00a0 \u00a0de \u00a0 servicio\u201d. \u00a0Lo \u00a0anterior \u00a0indica, \u00a0que \u00a0si \u00a0un \u00a0combustible \u00a0no \u00a0muestra la marca suministrada por Ecopetrol, necesariamente fue \u00a0sustra\u00eddo \u00a0de \u00a0uno \u00a0de \u00a0esos tubos distribuidores y sin autorizaci\u00f3n legal, en \u00a0otras \u00a0 \u00a0 palabras, \u00a0 \u00a0es \u00a0 \u00a0un \u00a0 \u00a0combustible \u00a0 \u00a0hurtado. \u00a0 \u00a0La \u00a0 \u00a0\u201cmarca\u201d \u00a0entonces, \u00a0es \u00a0un elemento auxiliar \u00a0suministrado \u00a0 por \u00a0 una \u00a0 empresa \u00a0 Estatal \u00a0que \u00a0sirve \u00a0para \u00a0diferenciar \u00a0los \u00a0combustibles \u00a0hurtados de los que han sido vendidos legalmente a los mayoristas, \u00a0de \u00a0 \u00a0 \u00a0no \u00a0 \u00a0 \u00a0existir \u00a0 \u00a0 la \u00a0 \u00a0 \u201cmarca\u201d, \u00a0ser\u00eda \u00a0casi \u00a0imposible \u00a0determinar cuando un combustible es hurtado o no, en el \u00a0caso \u00a0de \u00a0que \u00a0se \u00a0encuentre en un carrotanque ya en movimiento. Entonces exigir \u00a0que \u00a0se \u00a0sorprenda \u00a0a \u00a0los \u00a0delincuentes \u00a0pegados \u00a0al \u00a0oleoducto, no deja de ser \u00a0desproporcionado \u00a0teniendo en cuenta la inmensidad del mismo desde Puerto Berrio \u00a0hasta \u00a0 los \u00a0 l\u00edmites \u00a0 del \u00a0 departamento \u00a0 de \u00a0 Caldas \u00a0 que \u00a0ser\u00eda \u00a0nuestra \u00a0competencia\u2026\u201d \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0Finalmente, \u00a0se sostiene en la misma \u00a0decisi\u00f3n \u00a0que de todas maneras el hurto de combustible se sanciona en todas sus \u00a0formas, \u00a0esto \u00a0es \u00a0marcado o no marcado, pero lo que otorga la competencia a los \u00a0jueces \u00a0 penales \u00a0del \u00a0circuito \u00a0especializados \u00a0es \u00a0la \u00a0circunstancia \u00a0de\u00a0 \u00a0\u201cser \u00a0sustra\u00eddo \u00a0de \u00a0un \u00a0oleoducto, \u00a0 poliducto \u00a0 o \u00a0 gasoducto\u201d, \u00a0 remiti\u00e9ndose \u00a0a \u00a0continuaci\u00f3n \u00a0a \u00a0los \u00a0argumentos \u00a0que \u00a0fueron \u00a0expuestos \u00a0por la Fiscal\u00eda de segunda instancia en la resoluci\u00f3n de mayo 17 de \u00a02001 \u00a0cuyos apartes pertinentes se acaban de citar, para descartar los referidos \u00a0planteamientos del representante de la sociedad. \u00a0\u00a0<\/p>\n<p>Independientemente del acierto o no de estos \u00a0planteamientos \u00a0y \u00a0de \u00a0la \u00a0existencia \u00a0o no de la prueba para arribar a aquellas \u00a0conclusiones, \u00a0lo cierto es que la Fiscal\u00eda dio por demostrada la circunstancia \u00a0que \u00a0otorga \u00a0competencia \u00a0a \u00a0los \u00a0jueces \u00a0especializados, \u00a0esto \u00a0es que el hurto \u00a0recay\u00f3 \u00a0sobre \u00a0\u201cpetr\u00f3leo \u00a0o \u00a0sus \u00a0derivados \u00a0cuando \u00a0se sustraigan de un oleoducto, gasoducto, poliducto o \u00a0fuentes \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0inmediatas\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Por \u00a0ello \u00a0no \u00a0es \u00a0posible, \u00a0entonces, \u00a0aceptar \u00a0como \u00a0v\u00e1lidos \u00a0los \u00a0argumentos \u00a0expuestos \u00a0por \u00a0el \u00a0Juzgado Segundo Penal del Circuito Especializado \u00a0para \u00a0declinar \u00a0la \u00a0competencia, \u00a0y \u00a0de \u00a0acuerdo \u00a0con \u00a0los \u00a0cuales \u00a0\u201cas\u00ed \u00a0como deduce el Fiscal que dicho \u00a0crudo \u00a0fue \u00a0sustra\u00eddo \u00a0de un poliducto, nada impide al despacho, por no existir \u00a0prueba \u00a0 en \u00a0contrario, \u00a0conjeturar \u00a0que \u00a0haya \u00a0sido \u00a0sacado \u00a0de \u00a0un \u00a0centro \u00a0de \u00a0acopio\u201d, \u00a0pues \u00a0 ello \u00a0 configura \u00a0un \u00a0claro \u00a0desconocimiento \u00a0de \u00a0los \u00a0marcos \u00a0planteados \u00a0en \u00a0la \u00a0acusaci\u00f3n, \u00a0aspecto \u00a0que \u00a0no \u00a0es \u00a0posible \u00a0discutir en este \u00a0momento. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0este \u00a0orden \u00a0de \u00a0ideas, el conflicto ha de resolverse se\u00f1alando \u00a0que \u00a0es \u00a0el \u00a0Juez \u00a0Segundo \u00a0Penal \u00a0del \u00a0Circuito \u00a0Especializado \u00a0de Medell\u00edn el \u00a0competente para asumir el conocimiento del proceso. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, LA CORTE SUPREMA \u00a0DE JUSTICIA, SALA DE CASACION PENAL, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0DIRIMIR \u00a0la \u00a0presente \u00a0colisi\u00f3n negativa de competencia atribuyendo \u00a0el \u00a0conocimiento \u00a0del \u00a0presente \u00a0asunto \u00a0al \u00a0Juzgado \u00a0Segundo Penal del Circuito \u00a0Especializado de Medell\u00edn. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0DISPONER \u00a0la \u00a0inmediata \u00a0remisi\u00f3n \u00a0de las diligencias al Juzgado en \u00a0quien \u00a0se \u00a0radica \u00a0la \u00a0competencia, \u00a0dando aviso de lo aqu\u00ed decidido al Juzgado \u00a0Segundo Penal del Circuito de Bello. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>C\u00f3piese y c\u00famplase. \u00a0<\/p>\n<p>ALVARO ORLANDO PEREZ PINZON \u00a0<\/p>\n<p>FERNANDO \u00a0 ARBOLEDA \u00a0 RIPOLL \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0JORGE E. \u00a0C\u00d3RDOBA POVEDA \u00a0\u00a0<\/p>\n<p>HERMAN \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 GAL\u00c1N \u00a0CASTELLANOS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 CARLOS \u00a0 \u00a0 \u00a0A. \u00a0 \u00a0 \u00a0GALVEZ \u00a0ARGOTE \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>JORGE \u00a0ANIBAL \u00a0G\u00d3MEZ \u00a0GALLEGO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0EDGAR \u00a0LOMBANA TRUJILLO \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0E. \u00a0MEJIA ESCOBAR\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 NILSON PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>Teresa Ru\u00edz N\u00fa\u00f1ez \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 19128 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrado \u00a0Ponente \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0Dr. \u00a0JORGE \u00a0ANIBAL \u00a0GOMEZ \u00a0GALLEGO \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Aprobado Acta No. 10 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Bogot\u00e1 D. C., cinco de febrero de dos mil dos. \u00a0\u00a0 V I S T O S \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-6493","post","type-post","status-publish","format-standard","hentry","category-10"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/6493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=6493"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/6493\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=6493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=6493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=6493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}