{"id":6144,"date":"2023-09-08T16:24:11","date_gmt":"2023-09-08T16:24:11","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1779703-09-02\/"},"modified":"2023-09-08T16:24:11","modified_gmt":"2023-09-08T16:24:11","slug":"1779703-09-02","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1779703-09-02\/","title":{"rendered":"17797(03-09-02)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 17797 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>Dr. JORGE E. C\u00d3RDOBA \u00a0POVEDA \u00a0\u00a0<\/p>\n<p>Aprobado acta N\u00b0 101 \u00a0<\/p>\n<p>Bogot\u00e1, D. C., tres (3) de septiembre de dos \u00a0mil dos (2002). \u00a0\u00a0<\/p>\n<p>V I S T O S \u00a0<\/p>\n<p>Resuelve \u00a0la Corte la admisibilidad formal de \u00a0la \u00a0 \u00a0demanda \u00a0 \u00a0de \u00a0 \u00a0casaci\u00f3n \u00a0 \u00a0presentada \u00a0 \u00a0a \u00a0 nombre \u00a0 de \u00a0 GIOVANNY RAMIRO CRUZ ROJAS. \u00a0\u00a0<\/p>\n<p>A N T E C E D E N T E S \u00a0<\/p>\n<p>1. \u00a0Los \u00a0hechos \u00a0fueron \u00a0sintetizados \u00a0por el \u00a0juzgador de primera instancia, as\u00ed: \u00a0\u00a0<\/p>\n<p>\u201cCuenta \u00a0 la \u00a0denunciante \u00a0AURA \u00a0CECILIA \u00a0TOVAR \u00a0BENAVIDES, \u00a0quien es la ofendida, que en hora \u00a0cercana \u00a0a \u00a0las \u00a0siete \u00a0de \u00a0la noche del 26 de julio de 1999, el se\u00f1or GIOVANNY \u00a0RAMIRO \u00a0CRUZ \u00a0ROJAS, \u00a0al encontrarla en la calle por el sector Las Lunas de esta \u00a0ciudad \u00a0(Pasto), \u00a0cuando \u00a0iba \u00a0camino \u00a0al \u00a0lugar \u00a0de \u00a0trabajo de una hermana, la \u00a0invit\u00f3 \u00a0a \u00a0subir \u00a0al taxi que manejaba y, so pretexto de llevarla a su destino, \u00a0enrumb\u00f3 \u00a0el \u00a0veh\u00edculo \u00a0por \u00a0otras \u00a0rutas hasta llevarla al sector \u2018Las \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Malvas\u2019, en el corregimiento de Obonuco, donde \u00a0con \u00a0 el \u00a0 empleo \u00a0de \u00a0la \u00a0fuerza \u00a0la \u00a0accedi\u00f3 \u00a0carnalmente \u00a0en \u00a0contra \u00a0de \u00a0su \u00a0voluntad\u201d. \u00a0\u00a0<\/p>\n<p>2. \u00a0El \u00a0Juzgado Segundo Penal del Circuito de \u00a0Pasto, \u00a0mediante \u00a0sentencia \u00a0del \u00a024 \u00a0de \u00a0abril \u00a0de \u00a02000, \u00a0absolvi\u00f3 \u00a0al citado \u00a0procesado \u00a0por \u00a0el \u00a0delito de acceso carnal violento que le fuera imputado en la \u00a0resoluci\u00f3n de acusaci\u00f3n. \u00a0\u00a0<\/p>\n<p>3. \u00a0Inconforme \u00a0con la anterior decisi\u00f3n, el \u00a0Fiscal \u00a0Primero Seccional de dicha ciudad interpuso el recurso de apelaci\u00f3n, el \u00a0cual \u00a0al ser desatado por el Tribunal Superior de Pasto, el 23 de junio de 2000, \u00a0la \u00a0revoc\u00f3 \u00a0y, \u00a0en \u00a0su \u00a0lugar, \u00a0conden\u00f3 a Giovanny Ramiro Cruz Rojas a la pena \u00a0principal \u00a0de \u00a08 \u00a0a\u00f1os \u00a0y \u00a03 \u00a0meses de prisi\u00f3n y a la accesoria de rigor, como \u00a0autor del delito de acceso carnal violento. \u00a0\u00a0<\/p>\n<p>4. Ejecutoriada la sentencia, el defensor del \u00a0acusado \u00a0present\u00f3, \u00a0dentro \u00a0del \u00a0t\u00e9rmino legal, demanda de casaci\u00f3n contra la \u00a0sentencia de segunda instancia. \u00a0\u00a0<\/p>\n<p>LA\u00a0 \u00a0DEMANDA\u00a0 \u00a0DE\u00a0 CASACI\u00d3N \u00a0\u00a0<\/p>\n<p>Con fundamento en la causal primera, acusa al \u00a0Tribunal \u00a0 de \u00a0 haber \u00a0 transgredido \u00a0 el \u00a0 art\u00edculo \u00a0247 \u00a0del \u00a0C. \u00a0de \u00a0P. \u00a0P., \u00a0\u201cnorma \u00a0de \u00a0derecho sustancial que resulta del error \u00a0en \u00a0la \u00a0apreciaci\u00f3n \u00a0del \u00a0testimonio \u00a0de la denunciante y del reconocimiento de \u00a0excesivo \u00a0valor \u00a0probatorio de los no presenciales Fabio Recalde y Giomar Erazo, \u00a0y \u00a0desprecio \u00a0subjetivo por las pruebas testimoniales que favorecen al procesado \u00a0como \u00a0son \u00a0las \u00a0de \u00a0MAR\u00cdA CECILIA MIRAMAG AYALA, AURA \u00a0NELLY \u00a0RAM\u00cdREZ \u00a0INAG\u00c1N, \u00a0GILDARDO \u00a0AN\u00cdBAL \u00a0CRUZ \u00a0ROJAS, \u00a0JOS\u00c9 \u00a0CARLOS L\u00d3PEZ \u00a0e \u00a0 injurada \u00a0de \u00a0GIOVANNY \u00a0RAMIRO \u00a0CRUZ \u00a0ROJAS. Puesto que, campeando la duda, no \u00a0se \u00a0debi\u00f3 \u00a0condenar \u00a0por \u00a0no \u00a0existir \u00a0\u2018Certeza \u00a0 del \u00a0 hecho \u00a0 punible \u00a0 y \u00a0 de \u00a0 la \u00a0 responsabilidad \u00a0del \u00a0sindicado\u2019\u201d. \u00a0\u00a0<\/p>\n<p>Despu\u00e9s \u00a0de \u00a0copiar \u00a0un \u00a0fragmento \u00a0de \u00a0una \u00a0resoluci\u00f3n \u00a0dictada \u00a0por \u00a0la \u00a0Fiscal\u00eda, asegura que en la relaci\u00f3n sexual que \u00a0tuvieron \u00a0el \u00a0procesado \u00a0y \u00a0la \u00a0v\u00edctima \u00a0no \u00a0hubo \u00a0violencia, m\u00e1xime cuando su \u00a0procurado \u00a0no es persona corpulenta que le permitiera dominarla y de esa manera, \u00a0accederla, \u00a0ya \u00a0que, \u00a0a \u00a0su \u00a0juicio, \u00a0la \u00a0experiencia \u00a0ense\u00f1a \u00a0que \u00a0una persona \u00a0\u201cde \u00a0relativa igualdad de fuerzas no puede desvestir \u00a0a \u00a0otra \u00a0que se oponga a ello, si se lo propone, dejar\u00e1 huellas del forcejeo en \u00a0su \u00a0cuerpo \u00a0y, \u00a0ruptura \u00a0de \u00a0prendas \u00a0de \u00a0vestir \u00a0de \u00a0quien se resiste, y por la \u00a0inhibici\u00f3n \u00a0que \u00a0produce \u00a0la lucha, es fisiol\u00f3gicamente imposible mantener una \u00a0erecci\u00f3n \u00a0 \u00a0suficiente \u00a0 \u00a0para \u00a0 \u00a0penetrar \u00a0 \u00a0a \u00a0 \u00a0una \u00a0 prim\u00edpara&#8230;\u201d. \u00a0\u00a0<\/p>\n<p>Sostiene \u00a0que \u00a0los \u00a0hechos \u00a0narrados \u00a0por \u00a0la \u00a0v\u00edctima \u00a0no \u00a0resultan \u00a0cre\u00edbles, \u00a0dada \u00a0la \u00a0manera \u00a0como \u00a0los \u00a0relat\u00f3, lo que \u00a0respalda con copia de fragmentos jur\u00eddicos de dos doctrinantes. \u00a0\u00a0<\/p>\n<p>Despu\u00e9s \u00a0de \u00a0informar \u00a0que \u00a0la \u00a0v\u00edctima \u00a0se \u00a0present\u00f3 \u00a0a su oficina para desistir de la denuncia, insiste en que el Tribunal \u00a0no valor\u00f3 la prueba conforme a las reglas de la sana cr\u00edtica. \u00a0\u00a0<\/p>\n<p>En \u00a0consecuencia, solicita a la Sala casar la \u00a0sentencia impugnada.\u00a0 \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES\u00a0\u00a0 \u00a0DE\u00a0\u00a0 \u00a0LA\u00a0\u00a0 CORTE \u00a0\u00a0<\/p>\n<p>La \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0que \u00a0a nombre del \u00a0procesado \u00a0present\u00f3 \u00a0su defensor, no re\u00fane los requisitos formales que para su \u00a0admisi\u00f3n \u00a0estatu\u00eda \u00a0el numeral 3\u00b0 del art\u00edculo 225 del Decreto 2700 de 1991, \u00a0subrogado \u00a0por \u00a0el \u00a0art\u00edculo \u00a08\u00b0 \u00a0de \u00a0la \u00a0Ley \u00a0553 \u00a0de \u00a02000, \u00a0vigente para la \u00a0\u00e9poca. \u00a0\u00a0<\/p>\n<p>Ante \u00a0todo debe reiterarse que aqu\u00e9lla no es \u00a0un \u00a0escrito de libre formulaci\u00f3n, en el que de manera libre se pueda hacer toda \u00a0clase \u00a0de cuestionamientos a una sentencia que llega a esta sede amparada por la \u00a0doble \u00a0presunci\u00f3n \u00a0de \u00a0acierto y legalidad, sino que debe ser un escrito claro, \u00a0l\u00f3gico \u00a0y \u00a0sistem\u00e1tico \u00a0en \u00a0el \u00a0que \u00a0se \u00a0denuncian \u00a0los errores de juicio y de \u00a0procedimiento \u00a0cometidos \u00a0en \u00a0el \u00a0fallo, \u00a0al \u00a0tenor \u00a0de \u00a0las \u00a0causales expresa y \u00a0taxativamente \u00a0 se\u00f1aladas \u00a0 en \u00a0 la \u00a0ley, \u00a0se \u00a0demuestran \u00a0y \u00a0se \u00a0evidencia \u00a0su \u00a0trascendencia. \u00a0\u00a0<\/p>\n<p>Estas \u00a0exigencias \u00a0no fueron cumplidas por el \u00a0casacionista, destac\u00e1ndose entre sus desatinos los siguientes: \u00a0\u00a0<\/p>\n<p>1.\u00a0 \u00a0 No \u00a0identific\u00f3 \u00a0a \u00a0los \u00a0sujetos \u00a0procesales y la sentencia impugnada. \u00a0\u00a0<\/p>\n<p>2.\u00a0 Si bien funda el reparo en la causal \u00a0primera, \u00a0no \u00a0dice \u00a0si \u00a0opta \u00a0por la v\u00eda directa o por la indirecta, aunque del \u00a0desarrollo \u00a0de \u00a0la \u00a0censura se infiere que se decidi\u00f3 por la segunda, al atacar \u00a0la prueba. \u00a0\u00a0<\/p>\n<p>3.\u00a0 \u00a0No \u00a0indica \u00a0cu\u00e1l \u00a0fue \u00a0la \u00a0norma \u00a0sustancial \u00a0infringida \u00a0ni \u00a0su \u00a0sentido, \u00a0esto \u00a0es, \u00a0si \u00a0lo \u00a0fue \u00a0por \u00a0falta \u00a0de \u00a0aplicaci\u00f3n o por aplicaci\u00f3n indebida. \u00a0\u00a0<\/p>\n<p>4.\u00a0 \u00a0 No \u00a0 distingue \u00a0 entre \u00a0 normas \u00a0sustanciales \u00a0y procesales, pues le da la naturaleza de sustancial a un precepto \u00a0procesal, como lo es el art\u00edculo 247 del Decreto 2700 de 1991. \u00a0\u00a0<\/p>\n<p>5.\u00a0 \u00a0No \u00a0se\u00f1ala \u00a0la modalidad del yerro \u00a0cometido \u00a0por \u00a0el \u00a0Tribunal, si de hecho o de derecho, ni el falso juicio que lo \u00a0determin\u00f3, \u00a0si \u00a0de \u00a0existencia, \u00a0identidad, \u00a0legalidad \u00a0o \u00a0convicci\u00f3n, o si se \u00a0debi\u00f3 \u00a0a \u00a0un falso raciocinio, al haberse desconocido los postulados de la sana \u00a0cr\u00edtica. \u00a0\u00a0<\/p>\n<p>6.\u00a0 \u00a0Toda \u00a0la \u00a0disertaci\u00f3n \u00a0la reduce a \u00a0atacar \u00a0la \u00a0credibilidad otorgada por el Tribunal al testimonio de la v\u00edctima y \u00a0a \u00a0los \u00a0de \u00a0Fabio \u00a0Ricalde \u00a0y \u00a0Guiomar \u00a0Erazo \u00a0y negada a quienes favorec\u00edan al \u00a0procesado, \u00a0sin percatarse que esa discrepancia no configura error demandable en \u00a0casaci\u00f3n, \u00a0pues \u00a0el fallador tiene libertad para apreciar la prueba, dentro del \u00a0m\u00e9todo \u00a0de \u00a0la \u00a0persuasi\u00f3n \u00a0racional \u00a0que \u00a0nos \u00a0rige, \u00a0solo \u00a0limitada \u00a0por los \u00a0postulados de la sana cr\u00edtica. \u00a0\u00a0<\/p>\n<p>Ahora bien, si lo pretendido era denunciar que \u00a0al \u00a0valorar \u00a0los \u00a0elementos \u00a0de convicci\u00f3n se conculcaron ostensiblemente tales \u00a0principios \u00a0ha \u00a0debido \u00a0orientar \u00a0el reproche por la v\u00eda del error de hecho por \u00a0falso \u00a0raciocinio \u00a0e \u00a0indicar \u00a0cu\u00e1les \u00a0fueron \u00a0las \u00a0reglas \u00a0de \u00a0la ciencia, los \u00a0principios \u00a0de \u00a0la \u00a0l\u00f3gica o las reglas de la experiencia com\u00fan vulnerados, de \u00a0qu\u00e9 \u00a0manera \u00a0lo \u00a0fueron \u00a0y \u00a0c\u00f3mo \u00a0ese \u00a0desatino \u00a0llev\u00f3 \u00a0a declarar una verdad \u00a0distinta de la que revela el proceso. \u00a0\u00a0<\/p>\n<p>Aunque \u00a0en \u00a0la \u00faltima parte del discurso, el \u00a0libelista \u00a0manifiesta \u00a0que \u00a0se \u00a0infringieron \u00a0tales \u00a0postulados, \u00a0se queda en el \u00a0enunciado. \u00a0\u00a0<\/p>\n<p>Frente a los anotados desatinos de la demanda \u00a0y \u00a0dado \u00a0que \u00a0la \u00a0Corte, \u00a0en \u00a0virtud \u00a0del \u00a0principio \u00a0de \u00a0limitaci\u00f3n, \u00a0no puede \u00a0subsanarlos, se impone su inadmisi\u00f3n. \u00a0\u00a0<\/p>\n<p>Por \u00a0 \u00a0lo \u00a0 expuesto, \u00a0 la \u00a0 CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0SALA \u00a0DE \u00a0CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>R E S U E L V E \u00a0<\/p>\n<p>INADMITIR la demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0a \u00a0nombre de GIOVANNY RAMIRO \u00a0CRUZ ROJAS. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta \u00a0decisi\u00f3n \u00a0no \u00a0procede \u00a0ning\u00fan \u00a0recurso, \u00a0conforme \u00a0a lo que dispon\u00edan los art\u00edculos 226, subrogado por el 9\u00b0 \u00a0de \u00a0la Ley 553 de 2000, y 197 del C. de P. P. (Decreto 2700 de 1991, aplicable a \u00a0este caso). \u00a0\u00a0<\/p>\n<p>Comun\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>ALVARO ORLANDO P\u00c9REZ PINZ\u00d3N \u00a0<\/p>\n<p>FERNANDO \u00a0 ARBOLEDA \u00a0 RIPOLL \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0JORGE \u00a0 E. \u00a0C\u00d3RDOBA \u00a0POVEDA \u00a0\u00a0<\/p>\n<p>HERMAN \u00a0 GALAN \u00a0 CASTELLANOS \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CARLOS \u00a0AUGUSTO \u00a0G\u00c1LVEZ ARGOTE \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>JORGE \u00a0ANIBAL \u00a0G\u00d3MEZ \u00a0GALLEGO \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0EDGAR \u00a0 \u00a0 \u00a0LOMBANA \u00a0TRUJILLO \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 E. \u00a0 MEJIA \u00a0 ESCOBAR \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0NILSON E. PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>TERESA RU\u00cdZ NU\u00d1EZ \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Secretaria \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 17797 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente \u00a0 Dr. JORGE E. C\u00d3RDOBA \u00a0POVEDA \u00a0\u00a0 Aprobado acta N\u00b0 101 \u00a0 Bogot\u00e1, D. C., tres (3) de septiembre de dos \u00a0mil dos (2002). \u00a0\u00a0 V I S T O S \u00a0 Resuelve \u00a0la Corte la admisibilidad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-6144","post","type-post","status-publish","format-standard","hentry","category-10"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/6144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=6144"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/6144\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=6144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=6144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=6144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}