{"id":6042,"date":"2023-09-08T16:24:04","date_gmt":"2023-09-08T16:24:04","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1728319-03-02\/"},"modified":"2023-09-08T16:24:04","modified_gmt":"2023-09-08T16:24:04","slug":"1728319-03-02","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1728319-03-02\/","title":{"rendered":"17283(19-03-02)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Proceso No 17283 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACION PENAL \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>Dr.\u00a0 EDGAR LOMBANA TRUJILLO \u00a0<\/p>\n<p>Aprobado Acta Nro. 35 \u00a0<\/p>\n<p>Bogot\u00e1, D.C., diecinueve (19) de marzo de dos \u00a0mil dos (2002) \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Se resuelve sobre la solicitud de cesaci\u00f3n de \u00a0procedimiento \u00a0elevada \u00a0por \u00a0el se\u00f1or SANTIAGO SALAH ARGUELLO, condenado por el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1 \u00a0a \u00a0la \u00a0pena \u00a0principal \u00a0de cuatro (04) a\u00f1os de \u00a0prisi\u00f3n, por el delito de tr\u00e1fico de influencias de particular. \u00a0\u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>Fueron \u00a0relatados \u00a0as\u00ed \u00a0por \u00a0la \u00a0Unidad \u00a0de \u00a0Fiscal\u00edas \u00a0Delegadas \u00a0ante \u00a0el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1, al proferir la \u00a0resoluci\u00f3n de acusaci\u00f3n: \u00a0\u00a0<\/p>\n<p>\u201cSe contraen a que \u00a0la \u00a0se\u00f1ora \u00a0SARA \u00a0MAR\u00cdA RUIZ MORALES, a mediados de 1996, acudi\u00f3 a la oficina \u00a0del \u00a0abogado \u00a0SANTIAGO \u00a0SALAH ARGUELLO, en busca de ayuda para su hermana MELIDA \u00a0ESTHER, \u00a0quien \u00a0se \u00a0hallaba \u00a0afectada \u00a0con medida de aseguramiento de detenci\u00f3n \u00a0preventiva \u00a0por \u00a0Concierto \u00a0para \u00a0Delinquir, \u00a0Hurto \u00a0y Receptaci\u00f3n, resoluci\u00f3n \u00a0impugnada \u00a0y \u00a0que \u00a0en \u00a0tal \u00a0virtud \u00a0se \u00a0hallaba al Despacho del H. Fiscal JAVIER \u00a0ARMANDO \u00a0FLETESCHER, Y as\u00ed el togado SALAH exigi\u00f3, en principio la suma de dos \u00a0millones \u00a0de \u00a0pesos y luego diez m\u00e1s, para oficiar a trav\u00e9s de terceros por la \u00a0libertad \u00a0inmediata \u00a0de \u00a0la \u00a0encartada, \u00a0asegurando \u00a0que en la segunda instancia \u00a0saldr\u00eda \u00a0libre, \u00a0lo cual result\u00f3 fallido y en consecuencia SARA MAR\u00cdA exigi\u00f3 \u00a0la \u00a0devoluci\u00f3n \u00a0del \u00a0dinero entregado, del que apenas se le restituy\u00f3 la mitad \u00a0por el abogado.\u201d \u00a0\u00a0<\/p>\n<p>ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>1-. Con base en la denuncia instaurada por la \u00a0se\u00f1ora \u00a0Sara \u00a0Mar\u00eda \u00a0Ruiz \u00a0Morales, \u00a0La Fiscal\u00eda Sesenta y Siete Seccional de \u00a0Bogot\u00e1 \u00a0adelant\u00f3 \u00a0averiguaci\u00f3n \u00a0preliminar; \u00a0luego \u00a0abri\u00f3 \u00a0investigaci\u00f3n \u00a0y \u00a0vincul\u00f3 \u00a0mediante \u00a0indagatoria al se\u00f1or SANTIAGO SALAH ARGUELLO; y al resolver \u00a0su \u00a0situaci\u00f3n \u00a0jur\u00eddica provisionalmente, mediante resoluci\u00f3n del 11 de junio \u00a0de \u00a0 1997, \u00a0 le \u00a0 impuso \u00a0medida \u00a0de \u00a0aseguramiento \u00a0consistente \u00a0en \u00a0detenci\u00f3n \u00a0preventiva, \u00a0como \u00a0presunto responsable de tr\u00e1fico de \u00a0influencias \u00a0para \u00a0obtener \u00a0favor de servidor p\u00fablico, \u00a0consagrado \u00a0en \u00a0el \u00a0art\u00edculo \u00a0147 del C\u00f3digo Penal (Decreto 100 de 1980); y le \u00a0concedi\u00f3 detenci\u00f3n domiciliaria (folio 101 cdno. 1). \u00a0\u00a0<\/p>\n<p>2-. \u00a0Con \u00a0base en lo dispuesto en el numeral \u00a04\u00b0 \u00a0del \u00a0art\u00edculo \u00a0415 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento Penal (Decreto 2700 de \u00a01991), \u00a0con \u00a0providencia \u00a0del \u00a021 \u00a0de \u00a0octubre de 1997, la Fiscal\u00eda instructora \u00a0concedi\u00f3 \u00a0libertad \u00a0provisional \u00a0al \u00a0se\u00f1or \u00a0SALAH ARGUELLO (folio 99 cdno. 2). \u00a0\u00a0<\/p>\n<p>3-. \u00a0Despu\u00e9s de recaudar numerosas pruebas, \u00a0el \u00a024 \u00a0de \u00a0noviembre \u00a0de \u00a01997 se declar\u00f3 cerrada la investigaci\u00f3n (folio 164 \u00a0cdno. 2). \u00a0\u00a0<\/p>\n<p>4-. \u00a0Al calificar el m\u00e9rito del sumario, el \u00a015 \u00a0de \u00a0enero \u00a0de \u00a01998, \u00a0la \u00a0Fiscal\u00eda Doscientos Ocho Seccional, adscrita a la \u00a0Unidad \u00a0Primera \u00a0de \u00a0Delitos \u00a0contra \u00a0la \u00a0Administraci\u00f3n P\u00fablica, precluy\u00f3 la \u00a0investigaci\u00f3n \u00a0a \u00a0favor del se\u00f1or SANTIAGO SALAH ARGUELLO, y revoc\u00f3 la medida \u00a0de \u00a0aseguramiento que lo afectaba, tras estimar que la conducta imputada no tuvo \u00a0ocurrencia (folio 207 cdno. 2). \u00a0\u00a0<\/p>\n<p>5-. La decisi\u00f3n anterior fue apelada por el \u00a0Agente \u00a0del \u00a0Ministerio \u00a0P\u00fablico; \u00a0y \u00a0al resolver la impugnaci\u00f3n, la Unidad de \u00a0Fiscal\u00edas \u00a0 Delegadas \u00a0 ante \u00a0 el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1 \u00a0la \u00a0revoc\u00f3 \u00a0\u00edntegramente; \u00a0y \u00a0en su lugar, el 19 de junio de 1998, profiri\u00f3 resoluci\u00f3n de \u00a0acusaci\u00f3n \u00a0 contra \u00a0el \u00a0se\u00f1or \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO, \u00a0por \u00a0el \u00a0delito \u00a0de \u00a0tr\u00e1fico \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 influencias \u00a0 \u00a0 previsto \u00a0en \u00a0el \u00a0art\u00edculo \u00a0147 \u00a0del \u00a0C\u00f3digo Penal (Decreto 100 de \u00a01980), \u00a0reactiv\u00f3 \u00a0la \u00a0medida \u00a0de \u00a0aseguramiento, \u00a0y \u00a0dej\u00f3 \u00a0vigente la libertad \u00a0provisional. \u00a0\u00a0<\/p>\n<p>De \u00a0otra \u00a0parte, orden\u00f3 la compulsaci\u00f3n de \u00a0copias \u00a0\u201ca \u00a0fin de que el \u00a0funcionario \u00a0competente \u00a0investigue el punible de Estafa en que pudo incurrir el \u00a0encartado \u00a0 contra \u00a0 los \u00a0 intereses \u00a0patrimoniales \u00a0de \u00a0la \u00a0quejosa\u201d \u00a0 (folio \u00a0 23 \u00a0cdno. \u00a02\u00b0 \u00a0instancia \u00a0Fiscal\u00eda). \u00a0\u00a0<\/p>\n<p>6-. \u00a0La \u00a0causa fue adelantada por el Juzgado \u00a0Veintitr\u00e9s \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Bogot\u00e1, Despacho que, luego de practicar \u00a0pruebas \u00a0y \u00a0culminar la audiencia p\u00fablica, mediante sentencia del 12 de mayo de \u00a01999, \u00a0conden\u00f3 \u00a0al se\u00f1or SANTIAGO SALAH ARGUELLO a la pena principal de cuatro \u00a0(04) \u00a0a\u00f1os \u00a0de \u00a0prisi\u00f3n, \u00a0en \u00a0calidad \u00a0de \u00a0autor \u00a0responsable \u00a0de tr\u00e1fico \u00a0de \u00a0influencias \u00a0para obtener favor de servidor p\u00fablico, \u00a0a \u00a0interdicci\u00f3n de derechos y funciones p\u00fablicas por \u00a0el \u00a0mismo \u00a0lapso; \u00a0a multa por valor de cincuenta (50) salarios m\u00ednimos legales \u00a0mensuales; \u00a0y \u00a0le \u00a0neg\u00f3 \u00a0el \u00a0subrogado \u00a0de la condena de ejecuci\u00f3n condicional \u00a0(folio 131 cdno. 1). \u00a0\u00a0<\/p>\n<p>7-. \u00a0El \u00a0defensor \u00a0del procesado impugn\u00f3 la \u00a0decisi\u00f3n \u00a0de \u00a0primera instancia en busca de la absoluci\u00f3n, aduciendo que no se \u00a0demostr\u00f3 \u00a0la \u00a0existencia \u00a0del \u00a0hecho; \u00a0y \u00a0en \u00a0subsidio, \u00a0por el beneficio de la \u00a0duda. \u00a0\u00a0<\/p>\n<p>8-. \u00a0Al \u00a0desatar \u00a0la apelaci\u00f3n, el Tribunal \u00a0Superior \u00a0del \u00a0Distrito \u00a0Judicial de Bogot\u00e1, en fallo del 20 de agosto de 1999, \u00a0la \u00a0confirm\u00f3, con la modificaci\u00f3n consistente en ordenar el inmediato traslado \u00a0del \u00a0procesado \u00a0a la c\u00e1rcel que determinara el Instituto Nacional Penitenciario \u00a0y Carcelario INPEC (folio 17 cdno. Tribunal). \u00a0\u00a0<\/p>\n<p>9-. \u00a0El \u00a08 \u00a0de \u00a0marzo \u00a0de 2000 se produjo la \u00a0captura \u00a0del \u00a0se\u00f1or \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO, \u00a0y \u00a0fue trasladado a la Segunda \u00a0Estaci\u00f3n \u00a0de \u00a0Polic\u00eda \u00a0de Bogot\u00e1, por disposici\u00f3n del INPEC (folio 179 cdno. \u00a0Tribunal). \u00a0\u00a0<\/p>\n<p>10-. \u00a0Actuando en su propio nombre, SANTIAGO \u00a0SALAH \u00a0ARGUELLO, \u00a0abogado \u00a0de profesi\u00f3n, interpuso el recurso extraordinario de \u00a0casaci\u00f3n \u00a0contra \u00a0el \u00a0fallo \u00a0del \u00a0Tribunal Superior; la demanda fue formalmente \u00a0ajustada, \u00a0y \u00a0se \u00a0dispuso \u00a0el traslado a la Procuradur\u00eda Delegada con el fin de \u00a0que rinda concepto. \u00a0\u00a0<\/p>\n<p>11-. Mediante auto del 23 de agosto de 2000, \u00a0el \u00a0Juzgado \u00a0Veintitr\u00e9s \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Bogot\u00e1 \u00a0concedi\u00f3 \u00a0libertad \u00a0provisional \u00a0al \u00a0se\u00f1or \u00a0SANTIAGO SALAH ARGUELLO, en los t\u00e9rminos del art\u00edculo \u00a0415 \u00a0del \u00a0C\u00f3digo de Procedimiento Penal que reg\u00eda en ese momento, Decreto 2700 \u00a0de 1991 (folio 74 cdno. Corte). \u00a0\u00a0<\/p>\n<p>12-. \u00a0Debido \u00a0a \u00a0la \u00a0compulsaci\u00f3n de copias \u00a0ordenada \u00a0por \u00a0la \u00a0Unidad \u00a0de \u00a0Fiscal\u00edas Delegadas ante el Tribunal Superior de \u00a0Bogot\u00e1 \u00a0(actuaci\u00f3n \u00a0rese\u00f1ada \u00a0en \u00a0el \u00a0numeral 5\u00b0 de este ac\u00e1pite) el se\u00f1or \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO \u00a0fue \u00a0investigado por su presunta participaci\u00f3n en un \u00a0delito de estafa originado en los mismos acontecimientos. \u00a0\u00a0<\/p>\n<p>Este nuevo proceso culmin\u00f3 con preclusi\u00f3n, \u00a0dispuesta \u00a0mediante \u00a0resoluci\u00f3n \u00a0del \u00a012 \u00a0de \u00a0octubre \u00a0de \u00a01999 \u00a0por \u00a0el Fiscal \u00a0Seccional \u00a0Ciento Setenta y Cuatro adscrito a la Unidad Octava de delitos contra \u00a0la \u00a0Fe \u00a0P\u00fablica y el Patrimonio, providencia que, seg\u00fan constancia secretarial \u00a0se encuentra ejecutoriada (folios 53 y 57 cdno. Tribunal). \u00a0\u00a0<\/p>\n<p>En \u00a0esta resoluci\u00f3n los hechos investigados \u00a0se resumieron de la siguiente manera: \u00a0\u00a0<\/p>\n<p>\u201cA \u00a0 \u00a0esta \u00a0investigaci\u00f3n \u00a0se vincula al Doctor SANTIAGO SALAH ARGUELLO, en virtud a que el \u00a010 \u00a0de \u00a0octubre \u00a0de \u00a01996, \u00a0compareci\u00f3 a esa Unidad de Fiscal\u00edas Delegadas, la \u00a0quejosa \u00a0RUIZ \u00a0MORALES, \u00a0donde \u00a0dio \u00a0cuenta \u00a0c\u00f3mo el profesional del derecho le \u00a0hab\u00eda \u00a0 cobrado \u00a0 la \u00a0 suma \u00a0 de \u00a0$ \u00a02\u2019000.000.oo, \u00a0por un concepto jur\u00eddico y que este; (sic) seg\u00fan ella \u00a0estaba \u00a0acompa\u00f1ado \u00a0de resultados favorables por parte del Funcionario Judicial \u00a0que \u00a0estaba \u00a0adelantando \u00a0dicho \u00a0proceso. En donde se encontraba comprometida su \u00a0hermana \u00a0 \u00a0y \u00a0 \u00a0afectada \u00a0 \u00a0con \u00a0 \u00a0medida \u00a0 de \u00a0 aseguramiento \u00a0 de \u00a0 detenci\u00f3n \u00a0preventiva\u201d. \u00a0\u00a0<\/p>\n<p>DE LA PETICI\u00d3N \u00a0<\/p>\n<p>El \u00a0procesado \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO \u00a0en \u00a0memoriales \u00a0diferentes \u00a0solicita \u00a0que \u00a0su \u00a0caso \u00a0se \u00a0analice nuevamente desde la \u00a0\u00f3ptica \u00a0de \u00a0la \u00a0favorabilidad, \u00a0surgida \u00a0con \u00a0la \u00a0entrada en vigencia del nuevo \u00a0C\u00f3digo \u00a0Penal, \u00a0y \u00a0que, \u00a0en consecuencia, cese en su favor el procedimiento por \u00a0atipicidad sobreviniente de la conducta. \u00a0\u00a0<\/p>\n<p>Explica \u00a0que \u00a0el \u00a0delito \u00a0de \u00a0tr\u00e1fico \u00a0de \u00a0influencias \u00a0a \u00a0\u00e9l \u00a0imputado, \u00a0en \u00a0la \u00a0redacci\u00f3n \u00a0del \u00a0art\u00edculo 411 del nuevo \u00a0C\u00f3digo \u00a0Penal, \u00a0dej\u00f3 de ser punible respecto de los particulares, y que, en su \u00a0caso, \u00a0no \u00a0podr\u00eda \u00a0predicarse \u00a0que \u00a0se \u00a0trata \u00a0de \u00a0una \u00a0estafa \u00a0agravada en los \u00a0t\u00e9rminos \u00a0del \u00a0art\u00edculo 247 ib\u00eddem, toda vez que el supuesto delito de estafa \u00a0por \u00a0estos \u00a0mismos \u00a0hechos \u00a0ya \u00a0fue \u00a0investigado y culmin\u00f3 con preclusi\u00f3n a su \u00a0favor. \u00a0\u00a0<\/p>\n<p>Insiste en que la Sala debe resolver de plano \u00a0su \u00a0petici\u00f3n, aplicando de preferencia la Constituci\u00f3n Pol\u00edtica, debido a que \u00a0objetivamente \u00a0se \u00a0verifica \u00a0la causal que en su caso hace factible la cesaci\u00f3n \u00a0de \u00a0procedimiento, \u00a0sin necesidad de diferir la respuesta hasta que se expida la \u00a0sentencia \u00a0 \u00a0que \u00a0 \u00a0decida \u00a0 \u00a0de \u00a0 \u00a0fondo \u00a0 \u00a0el \u00a0 \u00a0recurso \u00a0 extraordinario \u00a0 de \u00a0casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA SALA \u00a0<\/p>\n<p>I-. \u00a0COMPETENCIA \u00a0DE LA CORTE EN VIRTUD DEL \u00a0RECURSO EXTRAORDINARIO DE CASACI\u00d3N \u00a0\u00a0<\/p>\n<p>1-. \u00a0Antes \u00a0de \u00a0abordar \u00a0el estudio del caso \u00a0concreto \u00a0se \u00a0estima \u00a0preciso recordar que la competencia que asiste a esta Sala \u00a0de \u00a0la \u00a0Corte \u00a0para \u00a0conocer del recurso extraordinario de casaci\u00f3n se define y \u00a0regula \u00a0por \u00a0los \u00a0art\u00edculos 235 de la Constituci\u00f3n Pol\u00edtica, 16 de la Ley 270 \u00a0de \u00a01996 (Estatutaria de la Administraci\u00f3n de Justicia), y 75 y 205 del C\u00f3digo \u00a0de Procedimiento Penal (Ley 600 de 2000). \u00a0\u00a0<\/p>\n<p>De aquella normatividad se infiere que cuando \u00a0un \u00a0 asunto \u00a0 llega \u00a0 a \u00a0 conocimiento \u00a0 de \u00a0la \u00a0Corte \u00a0en \u00a0virtud \u00a0del \u00a0recurso \u00a0extraordinario, \u00a0su \u00a0competencia \u00a0se encuentra restringida a decidir el problema \u00a0de \u00a0fondo \u00a0planteado en la demanda y con arreglo al principio de limitaci\u00f3n, de \u00a0suerte \u00a0que \u00a0mientras \u00a0la casaci\u00f3n se encuentra en tr\u00e1mite y antes de proferir \u00a0la \u00a0sentencia, \u00a0la \u00a0Sala no est\u00e1 facultada por la ley para dirimir incidentes o \u00a0asuntos \u00a0ajenos \u00a0al \u00a0recurso \u00a0extraordinario, \u00a0los \u00a0cuales \u00a0son \u00a0propios \u00a0de las \u00a0instancias; \u00a0 por \u00a0ejemplo, \u00a0devoluci\u00f3n \u00a0de \u00a0bienes, \u00a0cancelaci\u00f3n \u00a0de \u00a0medidas \u00a0cautelares, \u00a0libertad \u00a0provisional \u00a0del \u00a0procesado, favorabilidad, redenci\u00f3n de \u00a0pena \u00a0por \u00a0trabajo, \u00a0estudio \u00a0o ense\u00f1anza, permisos para salir del pa\u00eds, etc., \u00a0salvo las excepciones contempladas en disposiciones especiales. \u00a0\u00a0<\/p>\n<p>Se \u00a0insiste, \u00a0la \u00a0competencia \u00a0de \u00a0la \u00a0Corte \u00a0Suprema \u00a0de \u00a0Justicia \u00a0es \u00a0taxativamente \u00a0reglada \u00a0y \u00a0limitada; \u00a0las \u00a0normas que \u00a0establecen \u00a0la \u00a0competencia \u00a0de \u00a0los \u00a0funcionarios \u00a0judiciales tienen naturaleza \u00a0adjetiva \u00a0o \u00a0procesal, \u00a0y \u00a0\u00e9ste \u00a0tipo de disposiciones de orden p\u00fablico son de \u00a0obligatorio cumplimiento, salvo autorizaci\u00f3n expresa de la ley. \u00a0\u00a0<\/p>\n<p>Este \u00a0criterio \u00a0no \u00a0ha sufrido variaciones a \u00a0pesar \u00a0de \u00a0los cambios de legislaci\u00f3n, pues siempre se indican espec\u00edficamente \u00a0las \u00a0atribuciones \u00a0de \u00a0la \u00a0Sala \u00a0en \u00a0sede \u00a0de \u00a0casaci\u00f3n, entre las cuales no se \u00a0encuentra la de admitir ni adelantar incidentes de ninguna especie. \u00a0\u00a0<\/p>\n<p>2-. El recurso extraordinario de casaci\u00f3n se \u00a0rige \u00a0por \u00a0el principio dispositivo, es de naturaleza rogada, y las pretensiones \u00a0de \u00a0la \u00a0demanda \u00a0delimitan \u00a0la \u00a0competencia \u00a0de \u00a0la Sala de Casaci\u00f3n Penal, con \u00a0excepci\u00f3n \u00a0de \u00a0la \u00a0nulidad \u00a0que puede ser decretada oficiosamente en aras de la \u00a0protecci\u00f3n de las garant\u00edas fundamentales. \u00a0\u00a0<\/p>\n<p>No \u00a0 constituye \u00a0una \u00a0especie \u00a0de \u00a0tercera \u00a0instancia; \u00a0no consiste en someter a un nuevo juicio al procesado, ni en sede de \u00a0casaci\u00f3n \u00a0puede \u00a0postularse un debate probatorio generalizado y sin acatamiento \u00a0de \u00a0la t\u00e9cnica que le es inherente, puesto que el recurso extraordinario no fue \u00a0concebido \u00a0como \u00a0un \u00a0medio \u00a0o una herramienta adicional para litigar libremente, \u00a0sino \u00a0como \u00a0una excepcional manera de llevar a conocimiento del m\u00e1ximo tribunal \u00a0de \u00a0la \u00a0jurisdicci\u00f3n \u00a0ordinaria \u00a0el \u00a0fallo \u00a0proferido \u00a0por \u00a0el ad-quem, por las \u00a0causales \u00a0taxativamente \u00a0se\u00f1aladas en la ley, que hubiesen sido seleccionadas y \u00a0adecuadamente desarrolladas en la demanda. \u00a0\u00a0<\/p>\n<p>Entonces, el recurso de casaci\u00f3n se concibe \u00a0como \u00a0un \u00a0instituto \u00a0procesal extraordinario que busca remediar o poner fin a la \u00a0violaci\u00f3n \u00a0de la ley que hubiese ocurrido en la sentencia de segunda instancia, \u00a0por \u00a0errores de juicio o de actividad, y como tal comporta la elaboraci\u00f3n de un \u00a0juicio \u00a0l\u00f3gico \u00a0jur\u00eddico \u00a0sobre \u00a0la \u00a0sentencia \u00a0misma, \u00a0siguiendo el derrotero \u00a0trazado en las causales invocadas. \u00a0\u00a0<\/p>\n<p>En \u00a0virtud \u00a0del \u00a0recurso \u00a0extraordinario \u00a0se \u00a0constata \u00a0si \u00a0el \u00a0juzgador aplic\u00f3 adecuadamente la normatividad correspondiente \u00a0al \u00a0caso \u00a0concreto, con las finalidades de garantizar la efectividad del derecho \u00a0material \u00a0de \u00a0los \u00a0sujetos \u00a0procesales, \u00a0unificar \u00a0la \u00a0jurisprudencia nacional y \u00a0reparar los agravios inferidos con la sentencia contraria a la ley. \u00a0\u00a0<\/p>\n<p>3-. \u00a0 N\u00f3tese \u00a0que, \u00a0con \u00a0sujeci\u00f3n \u00a0a \u00a0la \u00a0legislaci\u00f3n \u00a0vigente, \u00a0ni \u00a0lo \u00a0atinente \u00a0a \u00a0la \u00a0libertad del procesado, ni a la \u00a0aplicaci\u00f3n \u00a0de \u00a0la \u00a0ley penal m\u00e1s favorable se encuentra entre las excepciones \u00a0que \u00a0habilitar\u00edan \u00a0a \u00a0la Sala para estudiar incidentes de esa naturaleza, antes \u00a0del \u00a0fallo \u00a0que \u00a0resuelva el fondo del recurso extraordinario de casaci\u00f3n, si a \u00a0ello hubiere lugar. \u00a0\u00a0<\/p>\n<p>La aplicaci\u00f3n preferencial de la norma penal \u00a0favorable, \u00a0derecho \u00a0fundamental \u00a0de los procesados, en la mayor\u00eda de los casos \u00a0incide \u00a0en \u00a0la \u00a0libertad, \u00a0tanto \u00a0que, muchas veces, con ocasi\u00f3n de un precepto \u00a0m\u00e1s \u00a0favorable los detenidos alcanzan los requisitos para recuperar su libertad \u00a0f\u00edsica. \u00a0\u00a0<\/p>\n<p>Debido \u00a0a \u00a0ello, \u00a0el \u00a0juez \u00a0competente \u00a0para \u00a0resolver \u00a0solicitudes \u00a0relativas a la libertad del procesado es el mismo llamado \u00a0a \u00a0 decidir \u00a0las \u00a0peticiones \u00a0que \u00a0involucren \u00a0el \u00a0principio \u00a0de \u00a0favorabilidad, \u00a0originado \u00a0en \u00a0la \u00a0sucesi\u00f3n de le la ley penal sustantiva, y de la ley procesal \u00a0penal con efectos sustantivos. \u00a0\u00a0<\/p>\n<p>4.-. \u00a0Si \u00a0se \u00a0trata \u00a0de \u00a0una \u00a0petici\u00f3n \u00a0de \u00a0libertad, \u00a0 redenci\u00f3n \u00a0 de \u00a0 pena \u00a0 por \u00a0 trabajo, \u00a0 estudio \u00a0o \u00a0ense\u00f1anza, \u00a0o \u00a0redosificaci\u00f3n \u00a0de \u00a0pena \u00a0por \u00a0favorabilidad, \u00a0elevada \u00a0mientras \u00a0el recurso de \u00a0casaci\u00f3n \u00a0se \u00a0encuentre \u00a0en \u00a0tr\u00e1mite, en principio y en t\u00e9rminos generales la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n Penal no es competente para resolverla de plano, pues seg\u00fan \u00a0las \u00a0circunstancias \u00a0corresponde \u00a0al \u00a0juez \u00a0de \u00a0primera \u00a0instancia, \u00a0al \u00a0juez de \u00a0ejecuci\u00f3n de penas, o se difiere hasta el fallo, como se ver\u00e1: \u00a0\u00a0<\/p>\n<p>4.1-. \u00a0El Juez que \u00a0profiri\u00f3 \u00a0 la \u00a0 condena \u00a0 en \u00a0primera \u00a0instancia. \u00a0De \u00a0conformidad \u00a0con el art\u00edculo 19 transitorio de la Ley 553 de 2000, que conserva \u00a0su \u00a0vigencia a pesar de haber empezado a regir el nuevo C\u00f3digo de Procedimiento \u00a0Penal, \u00a0es \u00a0el \u00a0Juez de primera instancia el competente para resolver peticiones \u00a0relativas \u00a0a la libertad que formulen los procesados cuya casaci\u00f3n se encuentra \u00a0en \u00a0tr\u00e1mite, \u00a0quedando \u00a0abarcadas dentro del concepto gen\u00e9rico de libertad las \u00a0solicitudes \u00a0de \u00a0redenci\u00f3n \u00a0de \u00a0pena destinada a la demostraci\u00f3n de requisitos \u00a0para \u00a0acceder \u00a0a \u00a0beneficios \u00a0administrativos, redosificaci\u00f3n de la condena por \u00a0favorabilidad, libertad provisional, etc. \u00a0\u00a0<\/p>\n<p>El \u00a0reconocimiento de redenci\u00f3n de pena por \u00a0trabajo, \u00a0estudio \u00a0o \u00a0ense\u00f1anza, \u00a0de suyo y en todos los casos influir\u00e1 en los \u00a0c\u00f3mputos \u00a0 indispensables \u00a0 para \u00a0 que \u00a0un \u00a0interno \u00a0acceda \u00a0a \u00a0los \u00a0beneficios \u00a0administrativos \u00a0y \u00a0finalmente pueda recuperar su libertad. Por ende, bajo estas \u00a0premisas, \u00a0el \u00a0Juez \u00a0de \u00a0primera \u00a0instancia \u00a0es \u00a0el competente para resolver las \u00a0solicitudes \u00a0de redenci\u00f3n de pena de los procesados cuya casaci\u00f3n se encuentre \u00a0en tr\u00e1mite. \u00a0\u00a0<\/p>\n<p>4.2-. \u00a0El Juez de \u00a0ejecuci\u00f3n \u00a0de \u00a0Penas \u00a0y \u00a0Medidas \u00a0de Seguridad. A este \u00a0funcionario, \u00a0seg\u00fan \u00a0lo \u00a0se\u00f1alado en el numeral 7\u00b0 del\u00a0 art\u00edculo 79 del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0(Ley \u00a0600 \u00a0de \u00a02000), \u00a0compete \u00a0resolver \u00a0las \u00a0peticiones \u00a0relativas \u00a0a \u00a0la \u00a0libertad \u00a0del \u00a0procesado o sobre favorabilidad, en \u00a0aquellos \u00a0eventos \u00a0en \u00a0los \u00a0cuales \u00a0el \u00a0tr\u00e1mite \u00a0posterior \u00a0al fallo de segunda \u00a0instancia \u00a0se \u00a0hubiese sujetado a las previsiones de la Ley 553 de 2000 entonces \u00a0vigente, \u00a0puesto \u00a0que \u00a0bajo \u00a0la \u00a0\u00e9gida \u00a0de \u00a0esta preceptiva dicho fallo quedaba \u00a0ejecutoriado el d\u00eda en que fuere proferido. \u00a0\u00a0<\/p>\n<p>En \u00a0este \u00a0caso \u00a0la \u00a0determinaci\u00f3n \u00a0de \u00a0la \u00a0competencia \u00a0deriva \u00a0de la ejecutoria del fallo de segunda instancia, situaci\u00f3n \u00a0que \u00a0se \u00a0mantiene \u00a0inc\u00f3lume \u00a0puesto \u00a0que \u00a0\u00fanicamente rigen hacia el futuro -no \u00a0retroactivamente- \u00a0los \u00a0efectos \u00a0derivados \u00a0de \u00a0los fallos de inexequibilidad de \u00a0algunas \u00a0de \u00a0las \u00a0disposiciones \u00a0de \u00a0Ley \u00a0553 \u00a0de \u00a02000, \u00a0declarada por la Corte \u00a0Constitucional en las sentencias C-252, C-260 y C-261 de 2001. \u00a0\u00a0<\/p>\n<p>4.3-. \u00a0Se difiere \u00a0hasta \u00a0el \u00a0fallo. \u00a0Si \u00a0la solicitud de aplicaci\u00f3n del \u00a0principio \u00a0de \u00a0favorabilidad tiene como \u00fanico objetivo la redosificaci\u00f3n de la \u00a0pena, \u00a0sin \u00a0estar \u00a0vinculada \u00a0a \u00a0petici\u00f3n \u00a0de \u00a0libertad \u00a0ni \u00a0a \u00a0los \u00a0beneficios \u00a0administrativos \u00a0consagrados en el C\u00f3digo Penitenciario y Carcelario (Ley 65 de \u00a01993), \u00a0la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n \u00a0Penal debe abstenerse de realizar los an\u00e1lisis \u00a0pertinentes \u00a0y, \u00a0mientras \u00a0no \u00a0var\u00ede \u00a0el \u00a0sentido \u00a0de \u00a0la petici\u00f3n, difiere el \u00a0estudio \u00a0propuesto al fallo que resuelva el recurso extraordinario de casaci\u00f3n, \u00a0si a ello hubiere lugar. \u00a0\u00a0<\/p>\n<p>No \u00a0 sobra \u00a0 advertir \u00a0 que \u00a0 hasta \u00a0 tal \u00a0pronunciamiento \u00a0de \u00a0la \u00a0Corte, \u00a0si \u00a0el \u00a0procesado \u00a0o \u00a0su \u00a0defensor pretenden la \u00a0aplicaci\u00f3n \u00a0favorable de las normas del actual estatuto punitivo, vincul\u00e1ndola \u00a0a \u00a0los \u00a0beneficios \u00a0administrativos \u00a0o \u00a0a \u00a0alguna \u00a0causal de libertad, para cuya \u00a0decisi\u00f3n \u00a0 resulte \u00a0 necesaria \u00a0la \u00a0readecuaci\u00f3n \u00a0de \u00a0la \u00a0pena, \u00a0la \u00a0solicitud \u00a0respectiva deber\u00e1 ser elevada al Juez de primera instancia. \u00a0\u00a0<\/p>\n<p>5.-. \u00a0En \u00a0sentencia \u00a0del 5 de septiembre de \u00a02001, \u00a0radicaci\u00f3n \u00a013.000, \u00a0con \u00a0ponencia \u00a0de \u00a0quien \u00a0ahora \u00a0funge \u00a0en la misma \u00a0calidad, \u00a0la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n \u00a0Penal \u00a0analiz\u00f3 \u00a0las \u00a0diversa \u00a0hip\u00f3tesis que \u00a0podr\u00edan \u00a0ocurrir \u00a0en \u00a0punto \u00a0de \u00a0la aplicaci\u00f3n de la ley penal m\u00e1s favorable, \u00a0as\u00ed: \u00a0\u00a0<\/p>\n<p>\u201c9-. Cabe anotar \u00a0que \u00a0en \u00a0punto de la favorabilidad las decisiones que esta prerrogativa implique \u00a0deben \u00a0ser \u00a0adoptadas \u00a0exclusivamente \u00a0por el funcionario competente, de acuerdo \u00a0con la fase o etapa en que se encuentre cada proceso. \u00a0\u00a0<\/p>\n<p>En \u00a0ese orden de ideas, pueden presentarse, \u00a0entre otras, las siguientes posibilidades: \u00a0\u00a0<\/p>\n<p>9.1-. Que el examen sobre favorabilidad deba \u00a0llevarse \u00a0a cabo mientras en el proceso se surte la segunda instancia de la fase \u00a0del \u00a0 \u00a0 juzgamiento. \u00a0 \u00a0 En \u00a0 \u00a0 esta \u00a0 \u00a0 hip\u00f3tesis \u00a0 \u00a0 pueden \u00a0 \u00a0ocurrir \u00a0 \u00a0dos \u00a0alternativas: \u00a0\u00a0<\/p>\n<p>9.1.1-. Si se trata de petici\u00f3n gen\u00e9rica y \u00a0simple \u00a0de \u00a0aplicaci\u00f3n \u00a0de \u00a0la \u00a0ley \u00a0m\u00e1s \u00a0favorable, \u00a0para \u00a0verificar \u00a0si \u00a0por \u00a0favorabilidad \u00a0deben \u00a0introducirse \u00a0algunas \u00a0modificaciones, \u00a0este \u00a0ejercicio se \u00a0difiere hasta el fallo. \u00a0\u00a0<\/p>\n<p>9.1.2-. \u00a0Si \u00a0la \u00a0aplicaci\u00f3n \u00a0favorable \u00a0de \u00a0alguna \u00a0norma va vinculada a petici\u00f3n de libertad provisional, u otros aspectos \u00a0como \u00a0redosificaci\u00f3n \u00a0de \u00a0pena \u00a0para acceder a beneficios administrativos, debe \u00a0resolverse \u00a0sobre \u00a0la \u00a0solicitud \u00a0de \u00a0libertad; \u00a0y \u00a0lo \u00a0que \u00a0se \u00a0decida sobre la \u00a0favorabilidad \u00a0tendr\u00e1 \u00a0car\u00e1cter \u00a0provisional \u00a0y as\u00ed deber\u00e1 declararse en los \u00a0autos. \u00a0\u00a0<\/p>\n<p>Al \u00a0producirse el fallo a que hubiere lugar \u00a0se resolver\u00e1 definitivamente sobre la libertad del procesado. \u00a0\u00a0<\/p>\n<p>9.2-. Que el examen sobre favorabilidad deba \u00a0llevarse \u00a0a \u00a0cabo \u00a0durante la ejecutoria del fallo de segunda instancia. En esta \u00a0hip\u00f3tesis pueden ocurrir dos alternativas: \u00a0\u00a0<\/p>\n<p>9.2.1-. Si se trata de petici\u00f3n gen\u00e9rica y \u00a0simple \u00a0de \u00a0aplicaci\u00f3n \u00a0de \u00a0la \u00a0ley \u00a0m\u00e1s \u00a0favorable, \u00a0para \u00a0verificar \u00a0si \u00a0por \u00a0favorabilidad \u00a0 deben \u00a0 introducirse \u00a0 algunas \u00a0 modificaciones, \u00a0se \u00a0carece \u00a0de \u00a0competencia para decidir sobre solicitudes de tal naturaleza. \u00a0\u00a0<\/p>\n<p>En este caso las cuestiones inherentes a la \u00a0favorabilidad \u00a0las resolver\u00e1, eventualmente, la Corte Suprema de Justicia si se \u00a0interpone \u00a0el recurso extraordinario de casaci\u00f3n, siempre que se decida casar y \u00a0\u00e9sta comporte redosificaci\u00f3n de pena. \u00a0\u00a0<\/p>\n<p>La \u00a0competencia \u00a0radicar\u00e1 \u00a0en \u00a0el \u00a0Juez de \u00a0Ejecuci\u00f3n \u00a0de \u00a0Penas \u00a0cuando \u00a0no \u00a0se impugne en casaci\u00f3n; o cuando habi\u00e9ndose \u00a0interpuesto \u00a0el \u00a0recurso \u00a0extraordinario, \u00a0el \u00a0fallo \u00a0de \u00a0la \u00a0Corte \u00a0no comporte \u00a0redosificaci\u00f3n punitiva. \u00a0\u00a0<\/p>\n<p>9.2.2-. Si se trata de solicitud de libertad \u00a0derivada \u00a0de \u00a0los \u00a0efectos \u00a0de \u00a0la \u00a0favorabilidad, debe resolver la petici\u00f3n de \u00a0libertad \u00a0el juez de segunda instancia; lo que \u00e9ste funcionario decida sobre la \u00a0favorabilidad \u00a0tendr\u00e1 \u00a0car\u00e1cter \u00a0provisional, y as\u00ed deber\u00e1 declararse en los \u00a0autos. \u00a0\u00a0<\/p>\n<p>La decisi\u00f3n definitiva sobre los efectos de \u00a0la favorabilidad ser\u00e1 adoptada, as\u00ed: \u00a0\u00a0<\/p>\n<p>-. \u00a0Eventualmente, \u00a0por la Corte Suprema de \u00a0Justicia \u00a0 \u00a0cuando \u00a0 \u00a0case \u00a0 \u00a0el \u00a0 \u00a0fallo \u00a0 \u00a0impugnado \u00a0 mediante \u00a0 el \u00a0 recurso \u00a0extraordinario. \u00a0\u00a0<\/p>\n<p>-. Por el Juez de Ejecuci\u00f3n de Penas, si no \u00a0se \u00a0hubiere \u00a0interpuesto \u00a0casaci\u00f3n, o si el fallo del recurso extraordinario no \u00a0est\u00e1 vinculado a la redosificaci\u00f3n punitiva. \u00a0\u00a0<\/p>\n<p>9.3-. Que el examen sobre favorabilidad deba \u00a0llevarse \u00a0a \u00a0cabo \u00a0mientras \u00a0el \u00a0proceso \u00a0surte la segunda instancia del Juez de \u00a0Ejecuci\u00f3n de Penas. \u00a0\u00a0<\/p>\n<p>En \u00a0esta \u00a0hip\u00f3tesis, las solicitudes sobre \u00a0favorabilidad \u00a0las \u00a0resuelve \u00a0el \u00a0Ad-quem \u00a0a trav\u00e9s de auto interlocutorio y de \u00a0manera \u00a0definitiva; \u00a0salvo, \u00a0claro \u00a0est\u00e1 \u00a0que se hubiese interpuesto el recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n \u00a0en \u00a0los eventos que fuere aplicable la Ley 553 de \u00a02000, y que la Corte al casar redosifique la pena. \u00a0\u00a0<\/p>\n<p>Por supuesto, contra el auto que resuelve en \u00a0segunda \u00a0instancia \u00a0los \u00a0asuntos \u00a0inherentes a la favorabilidad, en ning\u00fan caso \u00a0procede el recurso extraordinario de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Si \u00a0ocurre el fen\u00f3meno de la prescripci\u00f3n \u00a0sobre \u00a0alguno \u00a0de \u00a0los delitos imputados, \u00fanicamente se disminuye la pena en la \u00a0parte \u00a0que \u00a0correspondiere, \u00a0y \u00a0en esta eventualidad debe redosificar la pena el \u00a0Juez \u00a0de \u00a0Ejecuci\u00f3n o el Juez de primera instancia, seg\u00fan el caso.\u201d \u00a0\u00a0<\/p>\n<p>6-. \u00a0Es \u00a0corolario \u00a0de lo analizado en este \u00a0cap\u00edtulo \u00a0 que \u00a0si \u00a0la \u00a0Corte \u00a0conoce \u00a0de \u00a0un \u00a0asunto \u00a0en \u00a0virtud \u00a0del \u00a0recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n, \u00a0en \u00a0general \u00a0no \u00a0tiene competencia para resolver \u00a0aspectos \u00a0atinentes a la favorabilidad, y que, en los casos excepcionales que le \u00a0corresponde \u00a0hacerlo \u00a0difiere \u00a0el estudio hasta el fallo; y s\u00f3lo por excepci\u00f3n \u00a0en \u00a0la \u00a0sentencia resuelve al respecto, cuando case la sentencia y tal decisi\u00f3n \u00a0comporte redosificaci\u00f3n de pena. \u00a0\u00a0<\/p>\n<p>Lo \u00a0anterior, \u00a0sin \u00a0perjuicio \u00a0de \u00a0que deba \u00a0reconocer \u00a0y \u00a0declarar \u00a0una \u00a0causal \u00a0objetiva de extinci\u00f3n de la acci\u00f3n penal, \u00a0acaecida \u00a0por \u00a0aplicaci\u00f3n \u00a0de \u00a0la \u00a0ley \u00a0penal \u00a0m\u00e1s favorable, como se ver\u00e1 en \u00a0seguida. \u00a0\u00a0<\/p>\n<p>II-. \u00a0 \u00a0 EL \u00a0 \u00a0PROBLEMA \u00a0 \u00a0JUR\u00cdDICO \u00a0CONCRETO \u00a0\u00a0<\/p>\n<p>1-. Como viene de explicarse la competencia \u00a0de \u00a0la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n \u00a0Penal \u00a0es \u00a0taxativa \u00a0y \u00a0limitada \u00a0cuando \u00a0asume \u00a0el \u00a0conocimiento \u00a0de \u00a0un \u00a0asunto \u00a0en virtud del recurso extraordinario; no obstante, \u00a0por \u00a0excepci\u00f3n \u00a0y \u00a0teniendo \u00a0en \u00a0cuenta las circunstancias particulares que han \u00a0rodeado \u00a0el \u00a0proceso \u00a0penal \u00a0adelantado \u00a0al \u00a0se\u00f1or \u00a0SANTIAGO SALAH ARGUELLO, su \u00a0petici\u00f3n \u00a0es \u00a0susceptible \u00a0de \u00a0analizarse \u00a0ahora, \u00a0sin diferir el estudio de la \u00a0aplicaci\u00f3n \u00a0de \u00a0la \u00a0norma \u00a0penal \u00a0m\u00e1s favorable hasta el fallo que resuelva el \u00a0recurso \u00a0extraordinario, porque se trata de determinar si converge alguna causal \u00a0objetiva que extinga la acci\u00f3n penal. \u00a0\u00a0<\/p>\n<p>2-. Establece el art\u00edculo 39 del C\u00f3digo de \u00a0Procedimiento \u00a0Penal \u00a0(Ley 600 de 2000), que se podr\u00e1 cesar el procedimiento en \u00a0cualquier \u00a0momento \u00a0en que se demostrare la existencia de alguna de las causales \u00a0ah\u00ed \u00a0previstas, \u00a0entre \u00a0ellas, \u00a0que \u00a0la \u00a0actuaci\u00f3n \u00a0no \u00a0pueda proseguirse. Ese \u00a0momento \u00a0puede \u00a0ocurrir \u00a0dentro \u00a0del \u00a0tr\u00e1mite \u00a0de la casaci\u00f3n, pues el recurso \u00a0extraordinario \u00a0forma \u00a0parte \u00a0del \u00a0proceso penal establecido por la legislaci\u00f3n \u00a0nacional. \u00a0\u00a0<\/p>\n<p>3-. \u00a0Sin \u00a0embargo, \u00a0como lo ha reiterado la \u00a0jurisprudencia, \u00a0la \u00a0posibilidad \u00a0de \u00a0que \u00a0la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n Penal cese el \u00a0procedimiento \u00a0cuando \u00a0se \u00a0ha \u00a0dictado sentencia de segunda instancia y est\u00e1 en \u00a0tr\u00e1mite \u00a0 el \u00a0recurso \u00a0extraordinario, \u00a0procede \u00a0exclusivamente \u00a0frente \u00a0a \u00a0las \u00a0causales \u00a0 objetivas \u00a0 de \u00a0 extinci\u00f3n \u00a0 de \u00a0 la \u00a0 acci\u00f3n \u00a0penal \u00a0(verbi \u00a0gratia la muerte del procesado, la \u00a0prescripci\u00f3n, \u00a0 \u00a0 la \u00a0 \u00a0amnist\u00eda \u00a0 \u00a0y \u00a0 \u00a0la \u00a0 \u00a0descriminalizaci\u00f3n \u00a0 \u00a0de \u00a0 \u00a0la \u00a0conducta). \u00a0\u00a0<\/p>\n<p>Esto \u00a0porque \u00a0al \u00a0concurrir \u00a0una \u00a0de \u00a0tales \u00a0circunstancias \u00a0el \u00a0Estado \u00a0de \u00a0inmediato \u00a0pierde \u00a0la \u00a0facultad \u00a0de proseguir la \u00a0acci\u00f3n \u00a0penal \u00a0y \u00a0obviamente la Corte la competencia para desatar el recurso de \u00a0casaci\u00f3n, \u00a0debiendo \u00a0proceder al reconocimiento de la ocurrencia de la causal y \u00a0a disponer como consecuencia la cesaci\u00f3n del procedimiento. \u00a0\u00a0<\/p>\n<p>Bajo \u00a0tales \u00a0par\u00e1metros, \u00a0la \u00a0Sala \u00a0puede \u00a0decidir \u00a0la \u00a0solicitud \u00a0elevada por el procesado SALAH ARGUELLO sin necesidad de \u00a0diferir \u00a0la respuesta hasta la sentencia que resuelva el recurso extraordinario, \u00a0entendiendo, \u00a0claro est\u00e1, que la verificaci\u00f3n o descarte de la causal objetiva \u00a0invocada \u00a0como \u00a0generadora \u00a0de \u00a0la cesaci\u00f3n implica exclusivamente un ejercicio \u00a0hermen\u00e9utico, \u00a0 \u00a0y \u00a0 \u00a0en \u00a0 \u00a0ning\u00fan \u00a0 \u00a0sentido \u00a0 \u00a0estimaci\u00f3n \u00a0 o \u00a0 valoraci\u00f3n \u00a0probatoria. \u00a0\u00a0<\/p>\n<p>4-. El Tribunal Superior de Bogot\u00e1 conden\u00f3 \u00a0al \u00a0 se\u00f1or \u00a0 SANTIAGO \u00a0 SALAH \u00a0 ARGUELLO \u00a0 por \u00a0 el \u00a0 delito \u00a0 de \u00a0tr\u00e1fico \u00a0 de \u00a0 influencias \u00a0 para \u00a0 obtener \u00a0 favor \u00a0 de \u00a0servidor \u00a0p\u00fablico, \u00a0tipificado \u00a0en el art\u00edculo 147 del C\u00f3digo \u00a0Penal \u00a0(Decreto \u00a0100 \u00a0de \u00a01980), \u00a0modificado por la Ley 190 de 1995, que era del \u00a0siguiente tenor: \u00a0\u00a0<\/p>\n<p>\u201cEl que invocando \u00a0influencias \u00a0reales \u00a0o \u00a0simuladas reciba, haga dar o prometer para s\u00ed o para un \u00a0tercero \u00a0dinero \u00a0o \u00a0d\u00e1diva, con el fin de obtener cualquier beneficio por parte \u00a0de \u00a0servidor \u00a0p\u00fablico \u00a0en \u00a0asunto \u00a0que \u00a0\u00e9ste se encuentre conociendo o haya de \u00a0conocer, \u00a0 incurrir\u00e1 \u00a0 en \u00a0 prisi\u00f3n \u00a0 de \u00a0 cuatro \u00a0 (4) \u00a0 a \u00a0 seis\u00a0 \u00a0 (6) \u00a0a\u00f1os,\u2026\u201d \u00a0\u00a0<\/p>\n<p>5-. \u00a0El \u00a0C\u00f3digo \u00a0Penal vigente, Ley 559 de \u00a02000, \u00a0dej\u00f3 \u00a0de considerar el tr\u00e1fico de influencias cometido por particulares \u00a0como \u00a0un \u00a0delito \u00a0contra \u00a0la \u00a0administraci\u00f3n \u00a0p\u00fablica, \u00a0pues \u00a0reserv\u00f3 el tipo \u00a0\u00fanicamente \u00a0para \u00a0cuando \u00a0es \u00a0cometido \u00a0por servidores p\u00fablicos; y, en cambio, \u00a0ubic\u00f3 \u00a0esa \u00a0conducta, \u00a0cuando \u00a0es \u00a0cometida \u00a0por \u00a0un particular, en los delitos \u00a0contra \u00a0el \u00a0patrimonio \u00a0econ\u00f3mico, \u00a0como \u00a0circunstancia agravante de la estafa. \u00a0Obs\u00e9rvese: \u00a0\u00a0<\/p>\n<p>El \u00a0art\u00edculo \u00a0411 \u00a0del nuevo C\u00f3digo Penal \u00a0establece: \u00a0\u00a0<\/p>\n<p>\u201cTr\u00e1fico \u00a0de \u00a0influencias \u00a0de servidor p\u00fablico. El servidor p\u00fablico \u00a0que \u00a0utilice \u00a0indebidamente, \u00a0en \u00a0provecho \u00a0propio \u00a0o de un tercero, influencias \u00a0derivadas \u00a0del \u00a0ejercicio \u00a0del \u00a0cargo \u00a0o \u00a0de \u00a0la funci\u00f3n, con el fin de obtener \u00a0beneficio \u00a0de \u00a0parte \u00a0de \u00a0servidor \u00a0p\u00fablico \u00a0en \u00a0asunto \u00a0que \u00e9ste se encuentre \u00a0conociendo \u00a0o \u00a0haya \u00a0de conocer, incurrir\u00e1 en prisi\u00f3n de cuatro (4) a ocho (8) \u00a0a\u00f1os\u2026\u201d \u00a0\u00a0<\/p>\n<p>Por \u00a0su \u00a0parte, \u00a0el art\u00edculo 246 del nuevo \u00a0C\u00f3digo \u00a0 \u00a0 \u00a0 Penal \u00a0 \u00a0 \u00a0 tipifica \u00a0 \u00a0 \u00a0el \u00a0 \u00a0 \u00a0delito \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0estafa, \u00a0y \u00a0el 247 ib\u00eddem, contempla las \u00a0circunstancias \u00a0de \u00a0agravaci\u00f3n \u00a0punitiva \u00a0de esa conducta punible, indicando que la pena ser\u00e1 de cuatro (4) \u00a0a ocho (8) a\u00f1os, cuando: \u00a0\u00a0<\/p>\n<p>\u2026 \u00a0<\/p>\n<p>\u201c3-. Se invoquen \u00a0influencias \u00a0reales \u00a0o \u00a0simuladas \u00a0con el pretexto o con el fin de obtener de un \u00a0servidor \u00a0p\u00fablico \u00a0un \u00a0beneficio \u00a0en asunto que \u00e9ste se encuentre conociendo o \u00a0que haya de conocer.\u201d \u00a0\u00a0<\/p>\n<p>En \u00a0el \u00a0delito \u00a0de \u00a0estafa \u00a0previsto \u00a0en el \u00a0mencionado \u00a0art\u00edculo \u00a0246, \u00a0se \u00a0consagr\u00f3 como una circunstancia de agravaci\u00f3n \u00a0punitiva \u00a0la \u00a0conducta \u00a0del \u00a0implicado, \u00a0que \u00a0con \u00a0el \u00a0fin \u00a0de \u00a0estafar, invoque \u00a0influencias \u00a0reales \u00a0o \u00a0simuladas \u00a0para \u00a0obtener \u00a0de \u00a0un \u00a0servidor \u00a0p\u00fablico \u00a0un \u00a0beneficio \u00a0 en \u00a0 asunto \u00a0 que \u00a0 \u00e9ste \u00a0 se \u00a0 encuentre \u00a0 conociendo \u00a0o \u00a0haya \u00a0de \u00a0conocer. \u00a0\u00a0<\/p>\n<p>La \u00a0estafa \u00a0agravada \u00a0constituye, \u00a0pues, un \u00a0delito \u00a0en \u00a0el \u00a0cual \u00a0el \u00a0supuesto \u00a0de \u00a0hecho de la circunstancia de agravaci\u00f3n \u00a0punitiva \u00a0tiene \u00a0que \u00a0complementare \u00a0con \u00a0los \u00a0elementos \u00a0del \u00a0tipo \u00a0b\u00e1sico \u00a0de \u00a0estafa. \u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0las \u00a0cosas, \u00a0en \u00a0el \u00a0presente caso la \u00a0inducci\u00f3n \u00a0en error se obtiene con la invocaci\u00f3n de influencias que el abogado \u00a0SALAH \u00a0ARGUELLO \u00a0dijo \u00a0a \u00a0su cliente tener sobre el Fiscal de segunda instancia, \u00a0que \u00a0al \u00a0no \u00a0ser \u00a0ciertas, \u00a0o \u00a0no haber surtido efectos con el funcionario, como \u00a0parece \u00a0haber \u00a0ocurrido, \u00a0en \u00a0cualquiera \u00a0de \u00a0estas hip\u00f3tesis, al juzgar por el \u00a0resultado \u00a0adverso \u00a0a \u00a0la \u00a0hermana \u00a0de \u00a0quien contrat\u00f3 con el abogado y acept\u00f3 \u00a0entregar \u00a0mucho \u00a0m\u00e1s \u00a0de \u00a0lo \u00a0pactado \u00a0por \u00a0honorarios \u00a0profesionales, y con el \u00a0prop\u00f3sito \u00a0de \u00a0obtener \u00a0la \u00a0libertad de su pariente, constituyen el artificio o \u00a0enga\u00f1o, \u00a0a \u00a0trav\u00e9s \u00a0del \u00a0cual \u00a0el procesado habr\u00eda obtenido provecho il\u00edcito \u00a0personal \u00a0con \u00a0el \u00a0correlativo \u00a0desmedro \u00a0al \u00a0prestigio de la administraci\u00f3n de \u00a0justicia \u00a0y \u00a0al \u00a0patrimonio \u00a0de la v\u00edctima; pues la acriminaci\u00f3n legal de esta \u00a0conducta \u00a0no \u00a0deja duda de que el punible es pluriofensivo, en trat\u00e1ndose de la \u00a0circunstancia \u00a0de \u00a0agravaci\u00f3n espec\u00edfica prevista para la estafa en el numeral \u00a03\u00b0 del art\u00edculo 247 C\u00f3digo Penal vigente. \u00a0\u00a0<\/p>\n<p>6-. \u00a0La \u00a0exposici\u00f3n \u00a0de \u00a0motivos del nuevo \u00a0C\u00f3digo \u00a0Penal \u00a0(Ley \u00a0599 \u00a0de \u00a02000), \u00a0contenida en el oficio del 4 de agosto de \u00a01998, \u00a0que el Fiscal General de la Naci\u00f3n envi\u00f3 al Presidente del Senado de la \u00a0Rep\u00fablica, \u00a0cuyo \u00a0texto \u00a0fue \u00a0publicado \u00a0por \u00a0la \u00a0Fiscal\u00eda, \u00a0corrobora \u00a0que el \u00a0tr\u00e1fico \u00a0de influencias de particular definido en el art\u00edculo 147 del anterior \u00a0C\u00f3digo \u00a0Penal, \u00a0corresponde \u00a0en \u00a0la \u00a0nueva \u00a0normatividad a una circunstancia de \u00a0agravaci\u00f3n punitiva de la estafa: \u00a0\u00a0<\/p>\n<p>\u201cPara \u00a0el \u00a0delito \u00a0de \u00a0estafa \u00a0se establecen nuevas circunstancias de \u00a0agravaci\u00f3n: \u00a0la \u00a0primera referida a cuando el medio fraudulento tenga relaci\u00f3n \u00a0con \u00a0vivienda \u00a0de \u00a0inter\u00e9s social, como forma de reacci\u00f3n contra una costumbre \u00a0que \u00a0explota \u00a0la \u00a0necesidad \u00a0de \u00a0los sectores menos favorecidos; la segunda, que \u00a0hac\u00eda \u00a0parte \u00a0de \u00a0la ley 40 de 1.993, relativa al provecho il\u00edcito derivado de \u00a0un \u00a0delito \u00a0de \u00a0secuestro \u00a0o \u00a0extorsi\u00f3n; \u00a0la \u00a0tercera \u00a0corresponde \u00a0al \u00a0vigente \u00a0art\u00edculo \u00a0147 denominado Tr\u00e1fico de influencias para obtener favor de servidor \u00a0p\u00fablico.\u201d \u00a0\u00a0<\/p>\n<p>7-. \u00a0Tanto \u00a0la \u00a0sentencia del 12 de mayo de \u00a01999 \u00a0proferida \u00a0por \u00a0el \u00a0Juzgado \u00a0Veintitr\u00e9s \u00a0Penal \u00a0del \u00a0Circuito, como la de \u00a0segunda \u00a0instancia confirmatoria de la anterior, dictada el 20 de agosto de 1999 \u00a0por \u00a0el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1, \u00a0condenaron \u00a0al \u00a0se\u00f1or SANTIAGO SALAH \u00a0ARGUELLO \u00a0por \u00a0el \u00a0delito \u00a0de \u00a0tr\u00e1fico de influencias \u00a0para \u00a0 obtener \u00a0 favor \u00a0 de \u00a0 servidor \u00a0p\u00fablico, \u00a0que \u00a0consagraba \u00a0el \u00a0art\u00edculo \u00a0147 \u00a0del \u00a0C\u00f3digo Penal (Decreto 100 de 1980) vigente \u00a0para la \u00e9poca. \u00a0\u00a0<\/p>\n<p>El \u00a0fallo, \u00a0integrado por las sentencias de \u00a0instancia \u00a0convergentes \u00a0en el mismo sentido, fue recurrido en casaci\u00f3n, por lo \u00a0cual \u00a0sus \u00a0efectos quedaron en suspenso al concederse ese medio de impugnaci\u00f3n; \u00a0y \u00a0estando en tr\u00e1mite el recurso extraordinario entr\u00f3 a regir el nuevo C\u00f3digo \u00a0Penal \u00a0(Ley \u00a0599 \u00a0de 2000), que con relaci\u00f3n exclusivamente al sujeto activo de \u00a0la \u00a0conducta \u00a0punible \u00a0consistente \u00a0en \u00a0traficar \u00a0influencias, \u00a0tipificado en el \u00a0art\u00edculo \u00a0411 \u00a0ib\u00eddem, \u00a0lo \u00a0calific\u00f3 \u00a0con \u00a0la \u00a0exigencia \u00a0de ser servidor \u00a0p\u00fablico, \u00a0circunstancia por la \u00a0cual \u00a0no \u00a0puede \u00a0hablarse \u00a0hoy \u00a0de \u00a0sujeto \u00a0activo no calificado, lo que lleva a \u00a0predicar \u00a0la exclusi\u00f3n del agente para ese comportamiento, cuando no re\u00fane las \u00a0calidades \u00a0que \u00a0lo \u00a0califican, \u00a0de \u00a0acuerdo \u00a0a \u00a0lo \u00a0que \u00a0considera \u00a0la \u00a0ley como \u00a0servidor p\u00fablico. \u00a0\u00a0<\/p>\n<p>En \u00a0otras palabras, los particulares que no \u00a0tengan \u00a0 \u00a0permanente \u00a0 \u00a0o \u00a0 \u00a0transitoriamente \u00a0 la \u00a0 calidad \u00a0 de \u00a0 servidor \u00a0p\u00fablico \u00a0en \u00a0los t\u00e9rminos del \u00a0art\u00edculo \u00a020 \u00a0del \u00a0C\u00f3digo \u00a0Penal que hoy rige, no pueden ser sujeto activo del \u00a0punible \u00a0 de \u00a0 tr\u00e1fico \u00a0 de \u00a0 influencias \u00a0 tipificado \u00a0 en \u00a0el \u00a0art\u00edculo \u00a0411 \u00a0ib\u00eddem. \u00a0\u00a0<\/p>\n<p>Pese \u00a0a \u00a0ello, como la conducta ontol\u00f3gica \u00a0consistente \u00a0en \u00a0invocar influencias reales o simuladas con el pretexto o con el \u00a0fin \u00a0de \u00a0obtener \u00a0de \u00a0un \u00a0servidor \u00a0p\u00fablico un beneficio en asunto que \u00e9ste se \u00a0encuentre \u00a0conociendo \u00a0o \u00a0haya \u00a0de \u00a0conocer, fue recogida bajo el nomen iuris de \u00a0estafa \u00a0agravada \u00a0por \u00a0los \u00a0art\u00edculos \u00a0246 y 247 del nuevo C\u00f3digo Penal, a esta normatividad debe estarse, \u00a0en \u00a0 cuanto \u00a0 resultare \u00a0 favorable, \u00a0en \u00a0el \u00a0caso \u00a0del \u00a0se\u00f1or \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO. \u00a0\u00a0<\/p>\n<p>Tal \u00a0 ha \u00a0sido \u00a0la \u00a0tradici\u00f3n \u00a0jur\u00eddica \u00a0colombiana, \u00a0 pues \u00a0ya \u00a0la \u00a0Constituci\u00f3n \u00a0Pol\u00edtica \u00a0de \u00a01886 \u00a0(art\u00edculo \u00a026), \u00a0desarrollado \u00a0 por \u00a0el \u00a0art\u00edculo \u00a044 \u00a0de \u00a0la \u00a0Ley \u00a0153 \u00a0de \u00a01887, \u00a0\u201cen \u00a0materia \u00a0penal \u00a0la ley favorable o \u00a0permisiva \u00a0prefiere \u00a0en \u00a0los \u00a0juicios \u00a0a \u00a0la \u00a0odiosa \u00a0o restrictiva, a\u00fan cuando \u00a0aquella \u00a0sea \u00a0posterior \u00a0al \u00a0tiempo \u00a0en \u00a0que \u00a0se cometi\u00f3 el delito.\u201d\u00a0 \u00a0Situaci\u00f3n \u00a0que \u00a0se \u00a0mantiene \u00a0invariable \u00a0y \u00a0forma parte del debido proceso en la Carta de 1991 (articulo 29), \u00a0e \u00a0integra el principio de legalidad, norma rectora del derecho penal y procesal \u00a0penal, \u00a0consagrada \u00a0en \u00a0el \u00a0art\u00edculo \u00a06\u00b0 \u00a0de \u00a0los \u00a0c\u00f3digos \u00a0vigentes \u00a0de cada \u00a0especialidad. \u00a0\u00a0<\/p>\n<p>En ese orden de ideas, siendo imperativo de \u00a0rango \u00a0constitucional \u00a0la \u00a0aplicaci\u00f3n \u00a0del principio de favorabilidad, no queda \u00a0alternativa \u00a0distinta \u00a0a \u00a0la de concluir que, a partir de la entrada en vigencia \u00a0del \u00a0nuevo C\u00f3digo Penal (25 de julio de 2001), los particulares, entre ellos el \u00a0abogado \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO, \u00a0no pueden ser sujeto activo de tr\u00e1fico \u00a0de influencias, delito reservado \u00a0por \u00a0el \u00a0legislador exclusivamente a quienes tuvieren la calidad de servidor p\u00fablico. \u00a0\u00a0<\/p>\n<p>8-. \u00a0En \u00a0ese \u00a0orden \u00a0de ideas, no le asiste \u00a0raz\u00f3n \u00a0al \u00a0se\u00f1or \u00a0SANTIAGO SALAH ARGUELLO cuando pregona que la conducta a \u00e9l \u00a0atribuida \u00a0es \u00a0at\u00edpica \u00a0en el C\u00f3digo Penal vigente. La conducta consistente en \u00a0invocar \u00a0influencias \u00a0reales o simuladas con el pretexto o con el fin de obtener \u00a0de \u00a0un \u00a0servidor \u00a0p\u00fablico \u00a0un \u00a0beneficio \u00a0en \u00a0asunto \u00a0que \u00a0\u00e9ste \u00a0se \u00a0encuentre \u00a0conociendo \u00a0o \u00a0haya de conocer, se insiste, sigue consider\u00e1ndose punible por el \u00a0legislador, \u00a0es lesiva y merece reproche, por afectar preponderantemente el bien \u00a0jur\u00eddico \u00a0 del \u00a0patrimonio \u00a0y \u00a0en \u00a0otro \u00a0plano \u00a0los \u00a0bienes \u00a0jur\u00eddicos \u00a0de \u00a0la \u00a0administraci\u00f3n \u00a0p\u00fablica \u00a0y \u00a0la \u00a0administraci\u00f3n \u00a0de \u00a0justicia. \u00a0Por \u00a0ello, ese \u00a0comportamiento \u00a0ontol\u00f3gico \u00a0fue \u00a0recogido \u00a0bajo \u00a0el nomen iuris de estafa \u00a0agravada por los art\u00edculos 246 y \u00a0247 \u00a0del \u00a0nuevo C\u00f3digo Penal, que, como se dijo, es delito pluriofensivo cuando \u00a0la estafa se agrava por aquella circunstancia espec\u00edfica. \u00a0\u00a0<\/p>\n<p>9-. Como lo que se somete a investigaci\u00f3n y \u00a0juzgamiento \u00a0es \u00a0la \u00a0conducta \u00a0desplegada \u00a0por \u00a0el \u00a0sujeto \u00a0activo, independientemente del nomen iuris que a la \u00a0misma \u00a0asigne \u00a0el legislador, la Unidad de Fiscal\u00edas Delegadas ante el Tribunal \u00a0Superior \u00a0de Bogot\u00e1 entendi\u00f3 que adem\u00e1s del trafico \u00a0de \u00a0influencias \u00a0previsto \u00a0en \u00a0el \u00a0art\u00edculo \u00a0147 \u00a0del \u00a0C\u00f3digo \u00a0Penal \u00a0(Decreto \u00a0100 \u00a0de \u00a01980), \u00a0norma \u00a0destinada \u00a0a \u00a0salvaguardar \u00a0la \u00a0administraci\u00f3n \u00a0 p\u00fablica, \u00a0 quedaba \u00a0 pendiente \u00a0por \u00a0investigar \u00a0el \u00a0desmedro \u00a0patrimonial \u00a0sufrido \u00a0por la se\u00f1ora Sara Mar\u00eda Ruiz Morales, quien entreg\u00f3 al \u00a0abogado \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO \u00a0una importante suma de dinero, no catalogada \u00a0como \u00a0de \u00a0honorarios \u00a0profesionales, \u00a0para \u00a0que \u00a0influyera \u00a0ente \u00a0el funcionario \u00a0judicial \u00a0 que \u00a0 conoc\u00eda \u00a0el \u00a0proceso \u00a0penal \u00a0que \u00a0afectaba \u00a0a \u00a0la \u00a0hermana \u00a0de \u00a0ella. \u00a0\u00a0<\/p>\n<p>De \u00a0ese \u00a0modo, \u00a0entendiendo \u00a0que \u00a0podr\u00eda \u00a0presentarse \u00a0un \u00a0concurso de delitos entre el tr\u00e1fico \u00a0de \u00a0 \u00a0 \u00a0influencias \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 la \u00a0 \u00a0 estafa \u00a0de \u00a0que \u00a0pudo \u00a0ser \u00a0v\u00edctima \u00a0la \u00a0mencionada \u00a0se\u00f1ora, \u00a0la \u00a0Unidad \u00a0de \u00a0Fiscal\u00edas \u00a0de segunda instancia compuls\u00f3 \u00a0copias \u00a0para \u00a0que \u00a0el \u00a0competente \u00a0investigara \u00a0al abogado SALAH ARGUELLO por el \u00a0delito de estafa. \u00a0\u00a0<\/p>\n<p>En efecto, como se corrobora en el ac\u00e1pite \u00a0de \u00a0la \u00a0actuaci\u00f3n \u00a0procesal, a ra\u00edz de la compulsaci\u00f3n de copias ordenada por \u00a0la \u00a0Unidad \u00a0de \u00a0Fiscal\u00edas \u00a0Delegadas \u00a0ante \u00a0el Tribunal Superior de Bogot\u00e1, el \u00a0se\u00f1or \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO fue investigado por su presunta participaci\u00f3n \u00a0en \u00a0un \u00a0delito \u00a0de \u00a0estafa \u00a0originada \u00a0con \u00a0su \u00a0\u00fanica \u00a0conducta, \u00a0es decir, por \u00a0solicitar \u00a0dinero a la se\u00f1ora Sara Mar\u00eda Ruiz Morales, para interceder por una \u00a0hermana \u00a0de \u00a0ella \u00a0ante \u00a0un \u00a0Fiscal \u00a0de \u00a0la Rep\u00fablica que estaba conociendo una \u00a0investigaci\u00f3n penal que la implicaba. \u00a0\u00a0<\/p>\n<p>Este \u00a0nuevo proceso por el delito de estafa \u00a0culmin\u00f3 \u00a0con \u00a0preclusi\u00f3n, \u00a0dispuesta mediante resoluci\u00f3n del 12 de octubre de \u00a01999 \u00a0por \u00a0el \u00a0Fiscal \u00a0Seccional \u00a0Ciento \u00a0Setenta \u00a0y Cuatro adscrito a la Unidad \u00a0Octava \u00a0de \u00a0delitos \u00a0contra \u00a0la \u00a0Fe \u00a0P\u00fablica \u00a0y el Patrimonio, providencia que, \u00a0seg\u00fan \u00a0constancia \u00a0secretarial \u00a0se encuentra ejecutoriada (folios 53 y 57 cdno. \u00a0Tribunal). \u00a0\u00a0<\/p>\n<p>Es \u00a0evidente, entonces, que la conducta del \u00a0se\u00f1or \u00a0SANTIAGO SALAH ARGUELLO consistente en invocar influencias con el fin de \u00a0obtener \u00a0de \u00a0un \u00a0servidor \u00a0p\u00fablico (Fiscal de la Rep\u00fablica) un beneficio en un \u00a0asunto \u00a0que \u00a0se \u00a0encontraba \u00a0conociendo por raz\u00f3n de sus funciones, a cambio de \u00a0una \u00a0suma \u00a0de \u00a0dinero, ya fue investigada por la autoridad competente, y que con \u00a0relaci\u00f3n \u00a0 a \u00a0 ella \u00a0 ya \u00a0se \u00a0adopt\u00f3 \u00a0una \u00a0determinaci\u00f3n \u00a0que \u00a0tiene \u00a0firmeza \u00a0material. \u00a0\u00a0<\/p>\n<p>Vale \u00a0 decir, \u00a0 la \u00a0 preclusi\u00f3n \u00a0 de \u00a0la \u00a0investigaci\u00f3n \u00a0por el delito de estafa dispuesta mediante resoluci\u00f3n del 12 de \u00a0octubre \u00a0de \u00a01999 \u00a0por el Fiscal Seccional Ciento Setenta y Cuatro de Bogot\u00e1, a \u00a0favor \u00a0del \u00a0abogado \u00a0SALAH ARGUELLO, abarc\u00f3 toda su conducta atentatoria contra \u00a0el \u00a0patrimonio \u00a0de la se\u00f1ora Sara Mar\u00eda Ruiz Morales, la misma que en el nuevo \u00a0C\u00f3digo \u00a0 Penal \u00a0 fue \u00a0 recogida \u00a0 bajo \u00a0 el \u00a0 nomen \u00a0 iuris \u00a0 de \u00a0 estafa agravada. \u00a0\u00a0<\/p>\n<p>10-. \u00a0De \u00a0todo \u00a0lo \u00a0anterior, \u00a0dimanan tres \u00a0asertos a manera de conclusi\u00f3n: \u00a0\u00a0<\/p>\n<p>10.1-. \u00a0Por favorabilidad no puede juzgarse \u00a0ahora \u00a0 al \u00a0se\u00f1or \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO \u00a0por \u00a0el \u00a0delito \u00a0de \u00a0tr\u00e1fico \u00a0de \u00a0influencias, pues al tiempo \u00a0del \u00a0il\u00edcito, \u00a0\u201ca mediados \u00a0de \u00a01996\u201d, \u00e9l actu\u00f3 como \u00a0un \u00a0particular, \u00a0y en el nuevo C\u00f3digo Penal (Ley 599 de 2000), ese il\u00edcito fue \u00a0descriminalizado \u00a0bajo \u00a0ese \u00a0nomen iuris cuando ese comportamiento lo despliegan \u00a0los \u00a0 particulares, \u00a0 puesto \u00a0 que \u00a0s\u00f3lo \u00a0puede \u00a0ser \u00a0cometido \u00a0por \u00a0quien \u00a0sea \u00a0servidor p\u00fablico. \u00a0\u00a0<\/p>\n<p>10.2-. \u00a0Sin \u00a0duda alguna la conducta que el \u00a0C\u00f3digo \u00a0 Penal \u00a0 anterior \u00a0 (Decreto \u00a0100 \u00a0de \u00a01980) \u00a0consideraba \u00a0tr\u00e1fico \u00a0de \u00a0influencias \u00a0de \u00a0particular, fue recogida en el nuevo r\u00e9gimen penal (Ley 599 de \u00a02000) \u00a0 \u00a0bajo \u00a0 \u00a0el \u00a0 \u00a0nomen \u00a0 \u00a0iuris \u00a0 \u00a0de \u00a0 estafa \u00a0agravada. \u00a0\u00a0<\/p>\n<p>10-3-. \u00a0La \u00a0conducta \u00a0endilgada \u00a0al \u00a0se\u00f1or \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO, \u00a0que \u00a0permanece \u00a0invariablemente \u00a0punible, que en los \u00a0t\u00e9rminos \u00a0de \u00a0la legislaci\u00f3n penal actual corresponde a una estafa agravada, y \u00a0que \u00a0 tutela \u00a0preponderantemente \u00a0el \u00a0bien \u00a0jur\u00eddico \u00a0del \u00a0patrimonio, \u00a0ya \u00a0fue \u00a0investigada \u00a0por \u00a0las \u00a0autoridades \u00a0judiciales \u00a0competentes, \u00a0al punto que en su \u00a0favor \u00a0se precluy\u00f3 la investigaci\u00f3n, mediante una resoluci\u00f3n que tiene fuerza \u00a0de cosa juzgada material. \u00a0\u00a0<\/p>\n<p>De \u00a0ese \u00a0modo, \u00a0se \u00a0impone \u00a0concluir que la \u00a0actuaci\u00f3n \u00a0procesal, \u00a0vale \u00a0decir, \u00a0la acci\u00f3n penal no puede proseguirse en el \u00a0presente \u00a0caso, \u00a0debido a que, se insiste, el tr\u00e1fico \u00a0de \u00a0influencias para obtener favor de servidor p\u00fablico \u00a0cometido \u00a0por \u00a0particulares \u00a0(art\u00edculo 147 del C\u00f3digo Penal de 1980), dej\u00f3 se \u00a0ser \u00a0una \u00a0conducta aut\u00f3noma en el C\u00f3digo Penal vigente (Ley 599 de 2000), para \u00a0convertirse \u00a0en \u00a0una \u00a0circunstancia \u00a0agravante \u00a0de \u00a0la estafa; y debido a que la \u00a0\u00fanica \u00a0conducta que se reprocha al se\u00f1or SANTIAGO SALAH ARGUELLO, y que hoy lo \u00a0dejar\u00eda \u00a0incurso \u00a0en \u00a0una \u00a0estafa \u00a0agravada, ya fue materia de investigaci\u00f3n y \u00a0preclusi\u00f3n por el Fiscal Delegado competente. \u00a0\u00a0<\/p>\n<p>11-. \u00a0En s\u00edntesis, es claro que no podr\u00eda \u00a0juzgarse \u00a0nuevamente \u00a0su \u00a0conducta, \u00a0aunque haya sido recogida y consagrada como \u00a0punible \u00a0bajo \u00a0otro \u00a0nomen iuris (estafa agravada), porque el il\u00edcito atribuido \u00a0al \u00a0se\u00f1or \u00a0SALAH ARGUELLO (obtener dinero simulando influencias) ya fue materia \u00a0de \u00a0investigaci\u00f3n, precisamente por el Fiscal Seccional Ciento Setenta y Cuatro \u00a0adscrito \u00a0a \u00a0la \u00a0Unidad Octava de delitos contra la Fe P\u00fablica y el Patrimonio, \u00a0autoridad \u00a0que \u00a0mediante \u00a0resoluci\u00f3n \u00a0del \u00a012 \u00a0de octubre de 1999, precluy\u00f3 la \u00a0investigaci\u00f3n \u00a0por \u00a0el \u00a0delito \u00a0de \u00a0estafa, \u00a0y \u00a0porque esta providencia, seg\u00fan \u00a0constancia \u00a0 secretarial, \u00a0 se \u00a0 encuentra \u00a0en \u00a0firme \u00a0(folios \u00a053 \u00a0y \u00a057 \u00a0cdno. \u00a0Tribunal). \u00a0\u00a0<\/p>\n<p>12-. Expresa el art\u00edculo 19 del C\u00f3digo de \u00a0Procedimiento \u00a0Penal \u00a0(Ley \u00a0600 \u00a0de \u00a02000), \u00a0que \u00a0consagra \u00a0el \u00a0principio \u00a0de la \u00a0cosa \u00a0juzgada \u00a0como \u00a0norma \u00a0rectora \u00a0 \u00a0 del \u00a0 \u00a0 procedimiento \u00a0 \u00a0penal \u00a0 \u00a0colombiano, \u00a0 \u00a0que \u00a0 \u00a0\u201cla \u00a0persona \u00a0cuya situaci\u00f3n jur\u00eddica \u00a0haya \u00a0sido \u00a0definida por sentencia ejecutoriada o providencia que tenga la misma \u00a0fuerza \u00a0vinculante, \u00a0no \u00a0ser\u00e1 \u00a0sometida \u00a0a \u00a0una \u00a0nueva \u00a0actuaci\u00f3n por la misma \u00a0conducta, \u00a0aunque a esta se \u00a0le \u00a0 \u00a0 \u00a0 de \u00a0 \u00a0 \u00a0una \u00a0 \u00a0 \u00a0denominaci\u00f3n \u00a0 \u00a0 \u00a0jur\u00eddica \u00a0 \u00a0 \u00a0distinta\u201d (Se destaca). \u00a0\u00a0<\/p>\n<p>En \u00a0ese \u00a0orden \u00a0de \u00a0ideas, \u00a0la Sala cesar\u00e1 \u00a0procedimiento \u00a0a \u00a0favor \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO \u00a0y remitir\u00e1 el expediente al \u00a0Juzgado \u00a0Veintitr\u00e9s \u00a0Penal \u00a0del \u00a0Circuito \u00a0de Bogot\u00e1, Despacho que conoci\u00f3 de \u00a0este \u00a0asunto en primera instancia, bajo la radicaci\u00f3n 111-98, con el fin de que \u00a0cancele \u00a0todo \u00a0requerimiento \u00a0y \u00a0pendiente \u00a0que \u00a0el \u00a0mencionado se\u00f1or tenga por \u00a0raz\u00f3n exclusiva de este proceso penal. \u00a0\u00a0<\/p>\n<p>13-. \u00a0Huelga \u00a0advertir \u00a0que debido a que el \u00a0problema \u00a0jur\u00eddico \u00a0que \u00a0este \u00a0asunto involucra no se difiere hasta el fallo de \u00a0casaci\u00f3n, \u00a0la \u00a0sentencia \u00a0del \u00a020 \u00a0de \u00a0agosto de 1999 proferida por el Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1 no ha sido objeto de cuestionamiento alguno, pues, adem\u00e1s \u00a0de \u00a0que el examen de su estructura l\u00f3gico jur\u00eddica debe hacerse a la luz de la \u00a0normatividad \u00a0vigente \u00a0al \u00a0tiempo \u00a0de \u00a0su expedici\u00f3n, mientras no sea casada en \u00a0virtud \u00a0del \u00a0recurso extraordinario nada conspira contra la doble presunci\u00f3n de \u00a0legalidad y acierto que la respalda. \u00a0\u00a0<\/p>\n<p>De ah\u00ed que, debe quedar claro, la decisi\u00f3n \u00a0a \u00a0adoptar \u00a0no \u00a0corresponde \u00a0a \u00a0la \u00a0verificaci\u00f3n \u00a0de ning\u00fan error judicial, no \u00a0significa \u00a0el \u00a0reconocimiento \u00a0de la vulneraci\u00f3n de ning\u00fan derecho fundamental \u00a0de \u00a0los \u00a0que \u00a0deba \u00a0restablecer la Corte en virtud del recurso extraordinario de \u00a0casaci\u00f3n, \u00a0pues \u00a0un \u00a0juicio \u00a0en \u00a0tal \u00a0sentido \u00a0ni siquiera se ha emprendido, ni \u00a0equivale \u00a0a declarar la inocencia o la ausencia de responsabilidad del procesado \u00a0SANTIAGO SALAH ARGUELLO. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0la \u00a0Sala de \u00a0Casaci\u00f3n Penal de la Corte Suprema de Justicia, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>PRIMERO-. Declarar \u00a0que \u00a0en \u00a0el \u00a0presente \u00a0asunto \u00a0la \u00a0actuaci\u00f3n \u00a0procesal no puede proseguirse por \u00a0atipicidad \u00a0sobreviniente, \u00a0exclusivamente en consideraci\u00f3n al sujeto activo de \u00a0la \u00a0conducta \u00a0punible \u00a0de tr\u00e1fico de influencias para \u00a0obtener \u00a0favor \u00a0de \u00a0servidor p\u00fablico que consagraba el \u00a0art\u00edculo \u00a0147 \u00a0del \u00a0C\u00f3digo \u00a0Penal (Decreto 100 de 1980); y porque el delito de \u00a0estafa \u00a0 agravada, \u00a0actual \u00a0nomen \u00a0iuris \u00a0de \u00a0esa \u00a0conducta \u00a0cuando \u00a0es desplegada por un particular, ya fue \u00a0materia \u00a0de \u00a0juzgamiento, \u00a0y \u00a0precluida mediante decisi\u00f3n judicial que alcanz\u00f3 \u00a0firmeza material. \u00a0\u00a0<\/p>\n<p>En consecuencia, cesar procedimiento a favor \u00a0del \u00a0se\u00f1or \u00a0SANTIAGO \u00a0SALAH \u00a0ARGUELLO \u00a0identificado \u00a0con c\u00e9dula de ciudadan\u00eda \u00a0n\u00famero 19.314.094 de Bogot\u00e1. \u00a0\u00a0<\/p>\n<p>SEGUNDO-.\u00a0 \u00a0Remitir \u00a0el \u00a0expediente \u00a0al \u00a0Juzgado \u00a0Veintitr\u00e9s Penal del Circuito de Bogot\u00e1, \u00a0para \u00a0los \u00a0fines \u00a0indicados \u00a0en \u00a0el numeral doce (12) de la parte motiva de este \u00a0auto. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese y c\u00famplase \u00a0<\/p>\n<p>\u00c1LVARO ORLANDO P\u00c9REZ PINZ\u00d3N \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Aclaraci\u00f3n de voto \u00a0\u00a0<\/p>\n<p>FERNANDO \u00a0E. \u00a0ARBOLEDA \u00a0RIPOLL \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0JORGE \u00a0 \u00a0E. \u00a0 \u00a0C\u00d3RDOBA \u00a0POVEDA \u00a0\u00a0<\/p>\n<p>Aclaraci\u00f3n de voto \u00a0<\/p>\n<p>HERMAN \u00a0 GAL\u00c1N \u00a0CASTELLANOS \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CARLOS \u00a0 \u00a0A. \u00a0 \u00a0G\u00c1LVEZ \u00a0ARGOTE \u00a0\u00a0<\/p>\n<p>JORGE \u00a0 A. \u00a0 G\u00d3MEZ \u00a0GALLEGO \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0EDGAR LOMBANA TRUJILLO \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 E. \u00a0MEJ\u00cdA \u00a0ESCOBAR \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0NILSON PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0\u00a0 Proceso No 17283 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACION PENAL \u00a0 Magistrado Ponente: \u00a0 Dr.\u00a0 EDGAR LOMBANA TRUJILLO \u00a0 Aprobado Acta Nro. 35 \u00a0 Bogot\u00e1, D.C., diecinueve (19) de marzo de dos \u00a0mil dos (2002) \u00a0\u00a0 VISTOS \u00a0 Se resuelve sobre la solicitud de cesaci\u00f3n de \u00a0procedimiento \u00a0elevada \u00a0por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-6042","post","type-post","status-publish","format-standard","hentry","category-10"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/6042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=6042"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/6042\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=6042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=6042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=6042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}