{"id":60407,"date":"2023-12-22T21:39:42","date_gmt":"2023-12-22T21:39:42","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/12\/22\/stp14636-2021\/"},"modified":"2023-12-22T21:39:42","modified_gmt":"2023-12-22T21:39:42","slug":"stp14636-2021","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/12\/22\/stp14636-2021\/","title":{"rendered":"STP14636-2021"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>Magistrado \u00a0Ponente \u00a0<\/p>\n<p>STP14636-2021 \u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0n\u00ba 120111 \u00a0<\/p>\n<p>Acta \u00a0N\u00b0. 286 \u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D.C., dos (2) de noviembre de dos mil veintiuno (2021). \u00a0<\/p>\n<p>ASUNTO \u00a0<\/p>\n<p>Se \u00a0pronuncia la Sala acerca de la impugnaci\u00f3n formulada por el \u00a0apoderado del accionante WILMER \u00a0ORINDISITEO URRUTIA, \u00a0contra el fallo del 23 de septiembre de 2021, a trav\u00e9s del \u00a0cual el Tribunal Superior del Distrito Judicial de Cali, le neg\u00f3 \u00a0el \u00a0amparo de sus derechos fundamentales al debido proceso y a la \u00a0libertad, \u00a0presuntamente \u00a0vulnerados por \u00a0el Juzgado Cuarto de Ejecuci\u00f3n de Penas y Medidas de Seguridad \u00a0de la misma ciudad. \u00a0<\/p>\n<p>PROBLEMA \u00a0JUR\u00cdDICO \u00a0<\/p>\n<p>Corresponde \u00a0a la Sala determinar si en el presente asunto se encuentran \u00a0acreditados los requisitos generales y espec\u00edficos de \u00a0procedibilidad de la acci\u00f3n de tutela contra providencia \u00a0judicial y, en consecuencia, resulta procedente censurar por esta v\u00eda \u00a0excepcional el auto proferido por el Juzgado Cuarto de Ejecuci\u00f3n \u00a0de Penas y Medidas de Seguridad de Cali, en el que manifiesta estarse \u00a0a lo resuelto en el interlocutorio neg\u00f3 la solicitud de \u00a0libertad condicional requerida, en raz\u00f3n a la prohibici\u00f3n \u00a0contenida en el art\u00edculo 199 de la Ley 1098 de 2006. \u00a0<\/p>\n<p>ANTECEDENTES \u00a0PROCESALES \u00a0<\/p>\n<p>Mediante \u00a0auto del 13 de septiembre de 2021 la Sala de Decisi\u00f3n \u00a0Constitucional del Tribunal Superior de Cali, avoc\u00f3 \u00a0conocimiento de la acci\u00f3n de tutela y orden\u00f3 correr \u00a0traslado de la demanda a la autoridad judicial accionada con el fin \u00a0de garantizarle sus derechos de defensa y contradicci\u00f3n. \u00a0<\/p>\n<p>A \u00a0la presente actuaci\u00f3n fueron vinculado Centro de Servicios \u00a0Administrativos para os Juzgados de Ejecuci\u00f3n de Penas y \u00a0Medidas de Seguridad de Cali y al Centro Carcelario COJAM de Jamund\u00ed. \u00a0<\/p>\n<p>RESULTADOS \u00a0PROBATORIOS \u00a0<\/p>\n<p>1. \u00a0El Juzgado Cuarto de Ejecuci\u00f3n de Penas y Medidas de Seguridad \u00a0de Cali, manifest\u00f3 que ejerce la vigilancia de la sentencia \u00a0emitida contra el accionante. \u00a0<\/p>\n<p>Manifest\u00f3 \u00a0que con auto interlocutorio n\u00famero 1817 del 02 de enero de \u00a02017, neg\u00f3 la concesi\u00f3n del subrogado de la libertad \u00a0condicional al accionante, por expresa prohibici\u00f3n legal \u00a0contenida en el articulo 199 de la Ley 1098 de 2006, al haber \u00a0cometido delito contra la libertad, integridad y formaci\u00f3n \u00a0sexuales en perjuicio de una menor de edad, decisi\u00f3n que fue \u00a0objeto de los recursos de reposici\u00f3n y apelaci\u00f3n, \u00a0siendo confirmada la decisi\u00f3n de primera instancia por el \u00a0Juzgado Tercero Penal del Circuito con Funciones de conocimiento de \u00a0Cali. \u00a0<\/p>\n<p>Agreg\u00f3 \u00a0que despu\u00e9s de las decisiones anteriormente mencionadas, el \u00a0accionante ha continuado elevando peticiones para que se le conceda \u00a0el subrogado de la libertad condicional, a las que mediante autos de \u00a0sustanciaci\u00f3n le ha solicitado al mismo estarse a lo resuelto \u00a0en el interlocutorio 1817 del 02 de enero de 2017, pues no existiendo \u00a0norma que modifique la prohibici\u00f3n legal prevista en la Ley \u00a01098 de 2006, ello releva al Despacho de emitir nuevo pronunciamiento \u00a0de fondo al respecto. \u00a0<\/p>\n<p>Finaliza \u00a0solicitando se abstenga de tutelar los derechos fundamentales del \u00a0accionado pues no han sido vulnerados. \u00a0<\/p>\n<p>2. \u00a0El \u00a0director del Complejo Carcelario y Penitenciario de Jamund\u00ed, \u00a0manifest\u00f3 que lo solicitado no esta dentro de la orbita de \u00a0funciones del INPEC, que son funciones exclusivas de los Despachos \u00a0Judiciales, por lo cual solicit\u00f3 se desvinculara del tr\u00e1mite \u00a0constitucional pues no han vulnerado derechos fundamentales del \u00a0accionante, adem\u00e1s de la ausencia de legitimidad en la causa \u00a0por pasiva. \u00a0<\/p>\n<p>3. \u00a0El \u00a0Centro de Servicios de los Juzgados de Ejecuci\u00f3n de Penas y \u00a0Medidas de Seguridad de Cali, inform\u00f3 que en contra el \u00a0accionante se vigila un proceso por el Juzgado Cuarto de Ejecuci\u00f3n \u00a0de Penas y Medidas de Seguridad de la misma ciudad. Sin mas \u00a0precisiones ante el presente tr\u00e1mite constitucional. \u00a0<\/p>\n<p>FALLO \u00a0IMPUGNADO \u00a0<\/p>\n<p>La \u00a0Sala de Decisi\u00f3n Constitucional del Tribunal Superior de Cali \u00a0neg\u00f3 el amparo reclamado tras evidenciar que las razones que \u00a0tuvo el despacho para negar el beneficio de libertad condicional, se \u00a0fundaron en la aplicaci\u00f3n de la exclusi\u00f3n legal \u00a0establecida en el art\u00edculo 199 de la ley 1098 de 2006. Adem\u00e1s, \u00a0consider\u00f3 que la situaci\u00f3n del accionante fue \u00a0analizada, plasmando las razones por las cuales no era viable la \u00a0concesi\u00f3n del ya mencionado beneficio. \u00a0<\/p>\n<p>Ante \u00a0las nuevas solicitudes de volver a analizar el beneficio, el Juez de \u00a0ejecuci\u00f3n de penas se remite al auto interlocutorio n\u00famero \u00a01817 de 2017, que impuso la negativa en la concesi\u00f3n del \u00a0mismo. Lo cual consider\u00f3 razonable el Tribunal en la medida en \u00a0que las condiciones jur\u00eddicas reguladas por la ley 1098 de \u00a02006 no han variado, pues no han sido derogadas, ni han tenido \u00a0variaci\u00f3n en el r\u00e9gimen de exclusiones legales. Adem\u00e1s \u00a0de no haberse presentado argumentos nuevos por parte del accionante \u00a0que impongan el estudio y pronunciamiento, mediante auto \u00a0interlocutorio para desatar una nueva tesis que no haya sido \u00a0analizada al momento de negar el beneficio de libertad condicional. \u00a0<\/p>\n<p>Por \u00a0lo cual consider\u00f3 que no existe vulneraci\u00f3n de derechos \u00a0fundamentales de la parte accionante, en raz\u00f3n a que la orden \u00a0de estarse a lo resuelto, se funda en la vigencia de la ley 1098 de \u00a02006 y en especial del r\u00e9gimen de exclusiones legales. \u00a0<\/p>\n<p>LA \u00a0IMPUGNACI\u00d3N \u00a0<\/p>\n<p>Notificado \u00a0del contenido del fallo el accionante, present\u00f3 impugnaci\u00f3n, \u00a0pronunciamiento que manifest\u00f3 con su pu\u00f1o y letra sobre \u00a0el oficio de notificaci\u00f3n, inscribiendo sobre este \u201cyo \u00a0apelo\u201d. Sin mas pronunciamientos al respecto. \u00a0<\/p>\n<p>1. \u00a0De conformidad con lo establecido en el art\u00edculo \u00a02.2.3.1.2.1 del Decreto 1069 de 2015, modificado por el art\u00edculo \u00a01\u00ba del Decreto 1983 de 2017, \u00a0en armon\u00eda con el art\u00edculo 32 del Decreto 2591 de 1991, \u00a0la Sala es competente para pronunciarse sobre la impugnaci\u00f3n \u00a0interpuesta contra la decisi\u00f3n adoptada por la Sala de \u00a0Decisi\u00f3n Constitucional del Tribunal Superior de Cali, \u00a0del cual es su superior funcional. \u00a0<\/p>\n<p>2. \u00a0La \u00a0doctrina constitucional ha sido clara y enf\u00e1tica en se\u00f1alar \u00a0que cuando se trata de providencias judiciales, la acci\u00f3n de \u00a0tutela solamente resulta procedente de manera excepcional, pues como \u00a0regla general la inconformidad de las partes con lo resuelto por los \u00a0funcionarios judiciales ha de ser planteada y debatida en forma \u00a0oportuna, acudiendo para ello a los medios de impugnaci\u00f3n \u00a0instituidos en los c\u00f3digos de procedimiento. \u00a0<\/p>\n<p>No \u00a0obstante, por v\u00eda jurisprudencial se ha venido decantando el \u00a0alcance de tal postulado, dando paso a la procedencia de la acci\u00f3n \u00a0de tutela cuando se trate de actuaciones que carezcan de motivaci\u00f3n \u00a0o fundamento objetivo, contrariando su voluntad para hacer imperar la \u00a0arbitrariedad y el capricho del funcionario, o resulten \u00a0manifiestamente ilegales, de ah\u00ed que, por excepci\u00f3n se \u00a0permitir\u00e1 que el juez de tutela pueda intervenir en orden a \u00a0hacer cesar los efectos nocivos que la v\u00eda de hecho detectada \u00a0puede ocasionar en relaci\u00f3n con los derechos fundamentales. \u00a0<\/p>\n<p>En \u00a0ese sentido, la jurisprudencia ha se\u00f1alado que se incurre en \u00a0v\u00eda de hecho cuando existe; a) \u00a0un \u00a0defecto org\u00e1nico \u00a0(falta de competencia del funcionario judicial); b) \u00a0un \u00a0defecto procedimental absoluto \u00a0(desconocer el procedimiento legal establecido); c) \u00a0un \u00a0defecto f\u00e1ctico \u00a0(que la decisi\u00f3n carezca de fundamentaci\u00f3n probatoria); \u00a0d) \u00a0un \u00a0defecto material o sustantivo \u00a0(aplicar normas inexistentes o inconstitucionales); e) \u00a0un \u00a0error inducido \u00a0(que la decisi\u00f3n judicial se haya adoptado con base en el \u00a0enga\u00f1o de un tercero); f) \u00a0una \u00a0decisi\u00f3n sin motivaci\u00f3n \u00a0(ausencia de fundamentos f\u00e1cticos y jur\u00eddicos en la \u00a0providencia); g) \u00a0un \u00a0desconocimiento del precedente \u00a0y h) \u00a0la violaci\u00f3n \u00a0directa de la Constituci\u00f3n. \u00a0<\/p>\n<p>Bajo \u00a0ese derrotero, se impone recordarle a la parte accionante que siendo \u00a0la tutela un mecanismo de protecci\u00f3n excepcional frente a \u00a0providencias judiciales, su prosperidad va ligada al cumplimiento de \u00a0\u201cciertos \u00a0y rigurosos requisitos de procedibilidad\u201d \u00a0CC \u00a0C-590\/05 y T-332\/06 que implican \u00a0una carga para ella no \u00a0solamente en su planteamiento, sino tambi\u00e9n en su \u00a0demostraci\u00f3n, como lo ha expuesto la propia Corte \u00a0Constitucional, pues las sentencias que hacen tr\u00e1nsito a cosa \u00a0juzgada, gozan de la triple presunci\u00f3n de acierto, legalidad y \u00a0constitucionalidad, que brindan seguridad jur\u00eddica a las \u00a0decisiones judiciales, necesaria para la consolidaci\u00f3n del \u00a0Estado de Derecho. Solo por vulneraciones constitucionales, relativas \u00a0a los derechos fundamentales, mediante acciones reflejadas en los \u00a0hechos, oportuna y claramente planteados y demostrados, se puede \u00a0desvirtuar dicha presunci\u00f3n. \u00a0<\/p>\n<p>3. \u00a0En \u00a0el presente caso WILMER \u00a0ORINDISITEO URRUTIA no \u00a0demostr\u00f3 ninguno de los defectos que estructuran la denominada \u00a0v\u00eda de hecho, es decir, no acredit\u00f3 que las \u00a0providencias reprobadas est\u00e9n fundadas en conceptos \u00a0irrazonables o arbitrarios de tal trascendencia, que corresponda al \u00a0juez constitucional conjurarlos mediante este excepcional instrumento \u00a0de amparo para los derechos fundamentales invocados. \u00a0<\/p>\n<p>Por \u00a0el contrario, \u00a0las decisiones judiciales objeto de reproche estuvieron precedidas de \u00a0un an\u00e1lisis serio y ponderado de la controversia planteada, y \u00a0la interpretaci\u00f3n de la normativa pertinente, lo que llev\u00f3 \u00a0a concluir que el sentenciado no puede ser acreedor de la libertad \u00a0condicional que invoca, por expresa prohibici\u00f3n legal. \u00a0<\/p>\n<p>De \u00a0hecho, la Corte advierte prima \u00a0facie \u00a0que raz\u00f3n le asiste al Juzgado \u00a0de Ejecuci\u00f3n de Penas y Medidas de Seguridad, \u00a0pues su providencia se cimienta en lo dispuesto en el numeral 5\u00ba \u00a0del art\u00edculo 199 de la Ley 1098 de 2006, \u00a0que proh\u00edbe el otorgamiento de beneficios o subrogados como el \u00a0aqu\u00ed impetrado, cuando se trate delitos de homicidio, lesiones \u00a0personales dolosas, entre otros cometidos \u00a0contra ni\u00f1os, ni\u00f1as y adolescentes. \u00a0<\/p>\n<p>Como \u00a0en el sub \u00a0examine, \u00a0el promotor de la acci\u00f3n fue sentenciado por el punible de \u00a0acceso carnal violento en contra de un menor de edad, por tanto, no \u00a0pod\u00eda ser beneficiario de esa gracia, como acertadamente \u00a0decidi\u00f3 el funcionario judicial aqu\u00ed cuestionado. \u00a0<\/p>\n<p>Ahora \u00a0bien, la Ley 1098 de 2006 (C\u00f3digo de Infancia y Adolescencia), \u00a0tal y como lo ha se\u00f1alado la jurisprudencia, es un compendio \u00a0de normas positivas destinadas a garantizar la vigencia plena de los \u00a0derechos de los menores de edad. Esa protecci\u00f3n de los \u00a0derechos de los ni\u00f1os y adolescentes, consigna una disposici\u00f3n \u00a0de privilegio que impone la aplicaci\u00f3n preferente de las \u00a0normas del mismo frente a otras disposiciones del ordenamiento \u00a0jur\u00eddico. \u00a0<\/p>\n<p>En \u00a0ese sentido, el \u00a0art\u00edculo 199 de la Ley 1098 de 2006, trata espec\u00edficamente \u00a0sobre delitos por el cual fue condenado el actor, que, por afectar a \u00a0menores de edad, el legislador en su libertad de configuraci\u00f3n \u00a0normativa y con fundamento en la prevalencia de los derechos de los \u00a0ni\u00f1os, decidi\u00f3 brindar un mayor \u00e1mbito de \u00a0protecci\u00f3n a \u00e9stos, imponiendo entre otras, \u00a0prohibiciones para acceder a beneficios de quienes han incurrido en \u00a0conductas punibles contra ni\u00f1os, ni\u00f1as y adolescentes. \u00a0<\/p>\n<p>Ahora, \u00a0frente a la vigencia de las prohibiciones contenidas en el art\u00edculo \u00a0199 del C\u00f3digo de Infancia y Adolescencia, y en particular, en \u00a0lo que tiene que ver con la compatibilidad con la Ley 1709 de 2014, \u00a0la Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia, en \u00a0sede de tutelas1, \u00a0de forma pac\u00edfica ha exhibido lo siguiente: \u00a0<\/p>\n<p>\u00ab\u2026 \u00a0De otra parte, la exclusi\u00f3n de beneficios contenida en el \u00a0art\u00edculo 32 de la Ley 1709 de 2014, s\u00f3lo incorpor\u00f3 \u00a0algunos delitos para los cuales no proced\u00edan la suspensi\u00f3n \u00a0condicional de la ejecuci\u00f3n de la pena y la prisi\u00f3n \u00a0domiciliaria \u2013 dentro de los cuales enlist\u00f3 aquellos \u00a0contra la libertad, integridad y formaci\u00f3n sexuales \u2013, \u00a0dejando inc\u00f3lumes las disposiciones normativas que regulan el \u00a0subrogado de la libertad condicional, m\u00e1s a\u00fan, cuando \u00a0aquellas se encuentran revestidas de tal especificidad en el caso de \u00a0los delitos en los que la v\u00edctima sea un menor de edad. \u00a0<\/p>\n<p>En \u00a0consecuencia, lo que hizo el legislador en el par\u00e1grafo 1\u00ba \u00a0del art\u00edculo 32 de la Ley 1709 de 2014, fue establecer que la \u00a0libertad condicional prevista en el art\u00edculo 64 del C\u00f3digo \u00a0Penal, no se encuentra vedada para quienes hubieran sido condenados \u00a0por los punibles relacionados en el p\u00e1rrafo 2\u00ba del \u00a0art\u00edculo 68A del C\u00f3digo Penal, pero sin referirse, en \u00a0absoluto, a restricciones impuestas de manera expresa por el \u00a0legislador en disposiciones anteriores, como la contenida en el \u00a0numeral 5\u00ba del art\u00edculo 199 de la Ley 1098 de 2006, que \u00a0se refiere a delitos contra la vida, la integridad personal, \u00a0libertad, integridad y formaci\u00f3n sexuales o secuestro, \u00a0cometidos contra menores de edad\u2026\u00bb \u00a0(Negrilla fuera de \u00a0texto). \u00a0<\/p>\n<p>En \u00a0este contexto se colige que la negativa del subrogado penal deprecado \u00a0tuvo como sustento una prohibici\u00f3n de orden legal que excluye \u00a0el beneficio de la libertad condicional y otros, frente a infractores \u00a0de la ley penal cuyas v\u00edctimas son ni\u00f1os, ni\u00f1as \u00a0y adolescentes. Punto respecto del cual, como se observ\u00f3 en \u00a0precedencia, existe consenso sobre su aplicabilidad y prevalencia, en \u00a0atenci\u00f3n al inter\u00e9s superior que revisten los derechos \u00a0de los menores. \u00a0<\/p>\n<p>Respecto \u00a0a la inconformidad planteada por el accionante en lo concerniente al \u00a0auto de sustanciaci\u00f3n mediante el cual el Juzgado de Ejecuci\u00f3n \u00a0resolvi\u00f3 la solicitud de libertad condicional, \u00a0ordenando \u00a0estarse a lo resuelto en el Interlocutorio n\u00famero 1817 del \u00a02017, esta sala comparte la posici\u00f3n del Juzgado pues dentro \u00a0del plenario se logr\u00f3 evidenciar que dentro de las varias \u00a0solicitudes de libertad condicional presentadas por el accionante, en \u00a0ninguna se ha presentado situaciones novedosas que susciten el \u00a0desenvolvimiento de una tesis diferente a la desata dentro del \u00a0mencionado auto interlocutorio. \u00a0<\/p>\n<p>As\u00ed \u00a0las cosas, refulge evidente que \u00a0la autoridad demandada, aplic\u00f3 en debida forma el supuesto \u00a0normativo antes rese\u00f1ado, y, en consecuencia, su decisi\u00f3n \u00a0lejos \u00a0est\u00e1 de ser catalogada de arbitraria o caprichosa o \u00a0desconocedora de los derechos y garant\u00edas del penado. \u00a0<\/p>\n<p>Por \u00a0lo anterior se confirmar\u00e1 el fallo impugnado. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la Sala de Casaci\u00f3n Penal de la \u00a0Corte Suprema de Justicia, en Sala de Decisi\u00f3n de Tutelas No. \u00a01, administrando justicia en nombre de la Rep\u00fablica y por \u00a0autoridad de la ley, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>1. \u00a0CONFIRMAR la \u00a0negativa del amparo, conforme a las razones expuestas en la parte \u00a0motiva de esta decisi\u00f3n. \u00a0<\/p>\n<p>2. \u00a0Notificar \u00a0a las partes de conformidad con lo dispuesto en el art\u00edculo 30 \u00a0del Decreto 2591 de 1991. \u00a0<\/p>\n<p>3. \u00a0Enviar las \u00a0diligencias a la Corte Constitucional para su eventual revisi\u00f3n. \u00a0<\/p>\n<p>C\u00famplase \u00a0<\/p>\n<p>JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>PATRICIA \u00a0SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>NUBIA \u00a0YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Sentencia CSJ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0SP 24 de jun. 2014, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0reiterada en CSS STP8299-2014, STP13594-2019 y STP1021-2020. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0 Magistrado \u00a0Ponente \u00a0 STP14636-2021 \u00a0 Radicaci\u00f3n \u00a0n\u00ba 120111 \u00a0 Acta \u00a0N\u00b0. 286 \u00a0 Bogot\u00e1 \u00a0D.C., dos (2) de noviembre de dos mil veintiuno (2021). \u00a0 ASUNTO \u00a0 Se \u00a0pronuncia la Sala acerca de la impugnaci\u00f3n formulada por el \u00a0apoderado del accionante WILMER \u00a0ORINDISITEO URRUTIA, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,42],"tags":[],"class_list":["post-60407","post","type-post","status-publish","format-standard","hentry","category-30","category-noviembre"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/60407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=60407"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/60407\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=60407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=60407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=60407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}