{"id":60280,"date":"2023-12-22T21:39:34","date_gmt":"2023-12-22T21:39:34","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/12\/22\/ap5617-202152972\/"},"modified":"2023-12-22T21:39:34","modified_gmt":"2023-12-22T21:39:34","slug":"ap5617-202152972","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/12\/22\/ap5617-202152972\/","title":{"rendered":"AP5617-2021(52972)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>Magistrado \u00a0Ponente \u00a0<\/p>\n<p>AP5617-2021 \u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0N\u00b0 52972 \u00a0<\/p>\n<p>Aprobado \u00a0acta No 307 \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D. C., veinticuatro (24) de noviembre de dos mil veintiuno (2021). \u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>La \u00a0Corte decide sobre la admisibilidad de la demanda de casaci\u00f3n \u00a0presentada por el defensor de Agust\u00edn \u00a0M\u00e1rquez Solano \u00a0contra la sentencia del 23 de marzo de 2018, la cual el Tribunal \u00a0Superior del Distrito Judicial de Barranquilla confirm\u00f3 la \u00a0proferida el 27 de marzo de 2017 por el Juzgado S\u00e9ptimo Penal \u00a0del Circuito de la misma ciudad, que conden\u00f3 al nombrado como \u00a0autor del punible de estafa (Art. \u00a0246) \u00a0y fraude procesal (Art. \u00a0453). \u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0recuento procesal1, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0se desprende que mediante escritura p\u00fablica No 2012 del 27 de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0octubre de 2000, la familia M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jim\u00e9nez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0conformada por Agust\u00edn \u00a0 \u00a0 \u00a0 \u00a0 \u00a0M\u00e1rquez Solano, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Hortensia Jim\u00e9nez y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sus hijos Adis \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Hortensia, Ariel Agust\u00edn, Ricardo Adolfo y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jorge Miguel M\u00e1rquez Jim\u00e9nez, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0decidieron crear la sociedad M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jim\u00e9nez &amp; CIA S. en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0C. Acto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0inscrito en la C\u00e1mara de Comercio de Barranquilla el 9 de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0noviembre de ese a\u00f1o bajo el n\u00famero 89.801, con el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0objeto de desarrollar labores de ferreter\u00eda. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>2. Se determin\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que cada socio tendr\u00eda participaci\u00f3n de 2500 cuotas, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0con un valor de $2.500.000. Igualmente se designaron como socios \u00a0 \u00a0 \u00a0 \u00a0 \u00a0gestores a \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Hortensia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jim\u00e9nez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Agust\u00edn \u00a0 \u00a0 \u00a0 \u00a0 \u00a0M\u00e1rquez Solano, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0con \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la funci\u00f3n de administrar y representar a la sociedad, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0realizando asimismo actos propios del giro ordinario de los \u00a0 \u00a0 \u00a0 \u00a0 \u00a0negocios. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>3. El \u00a0 \u00a0 \u00a0 \u00a0 \u00a04 de marzo de 2009 la junta de socios decidi\u00f3 remover \u00a0 \u00a0 \u00a0 \u00a0 \u00a0legalmente de su cargo a \u00a0 \u00a0 \u00a0 \u00a0 \u00a0M\u00e1rquez Solano \u2013hasta \u00a0 \u00a0 \u00a0 \u00a0 \u00a0entonces representante legal de la empresa-, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en raz\u00f3n de la intranquilidad que les generaba la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0administraci\u00f3n de los negocios de la sociedad en sus manos, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0pues con sus acciones se desmejor\u00f3 el patrimonio social. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Algunas de ellas: i) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la venta de una finca con matricula inmobiliaria No. 045-24745 ii) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la hipoteca del inmueble con matricula inmobiliaria No. 040-369110, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0con su respectivo garaje, adem\u00e1s, iii) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0los locales comerciales de la sociedad con matr\u00edcula \u00a0 \u00a0 \u00a0 \u00a0 \u00a0inmobiliaria No. 040-369106 y 040-369107, los cuales se encontraban \u00a0 \u00a0 \u00a0 \u00a0 \u00a0cerrados sin raz\u00f3n justificable. Esta determinaci\u00f3n se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0protocoliz\u00f3 en escritura p\u00fablica No. 468 del 18 de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0marzo hoga\u00f1o, inscrita en la C\u00e1mara de Comercio el 31 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del mismo mes y a\u00f1o. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>4. Por \u00a0 \u00a0 \u00a0 \u00a0 \u00a0otro lado, el 13 de junio de 2008, mediante documento privado No. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0140.374 suscrito por Shirly \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Eljadue Escobar \u00a0 \u00a0 \u00a0 \u00a0 \u00a0se constituy\u00f3 la sociedad Davisha \u00a0 \u00a0 \u00a0 \u00a0 \u00a0E.U., \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que posteriormente por medio de documento No. 150.945 el 13 de julio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de 2009 se transform\u00f3 en Sociedad por Acciones Simplificada \u00a0 \u00a0 \u00a0 \u00a0 \u00a0bajo la denominaci\u00f3n Davisha \u00a0 \u00a0 \u00a0 \u00a0 \u00a0S.A.S. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y a trav\u00e9s de acta No. 2 del 23 de julio de 2009 nombr\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0como gerente a Agust\u00edn \u00a0 \u00a0 \u00a0 \u00a0 \u00a0M\u00e1rquez Solano. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>5. Posteriormente, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el 30 de julio de 2009 se realiz\u00f3 la venta de cinco inmuebles \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u2013un \u00a0 \u00a0 \u00a0 \u00a0 \u00a0apartamento, dos garajes y dos locales comerciales- por \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la suma de $30.000.000, los cuales pertenec\u00edan a la sociedad \u00a0 \u00a0 \u00a0 \u00a0 \u00a0M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jim\u00e9nez &amp; CIA S en C \u00a0 \u00a0 \u00a0 \u00a0 \u00a0comprados por la empresa Davisha \u00a0 \u00a0 \u00a0 \u00a0 \u00a0S.A.S. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Transacci\u00f3n \u00a0ejecutada por el procesado, a\u00fan cuando ya \u00a0 \u00a0 \u00a0 \u00a0 \u00a0no ten\u00eda la representaci\u00f3n legal de la empresa \u00a0 \u00a0 \u00a0 \u00a0 \u00a0vendedora. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>6. Dicho \u00a0 \u00a0 \u00a0 \u00a0 \u00a0negocio jur\u00eddico se protocoliz\u00f3 ante la Notar\u00eda \u00a0 \u00a0 \u00a0 \u00a0 \u00a012 de Barranquilla con escritura p\u00fablica No. 678, y adem\u00e1s \u00a0 \u00a0 \u00a0 \u00a0 \u00a0se registr\u00f3 el 13 de agosto de ese mismo a\u00f1o, como \u00a0 \u00a0 \u00a0 \u00a0 \u00a0consta en los certificados No. 040-369104, 040-369106, 040-369107, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0040-369110 en la Oficina \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de Registro de Instrumentos P\u00fablicos y Privados \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de la misma ciudad, enga\u00f1ando a sus socios y con ello \u00a0 \u00a0 \u00a0 \u00a0 \u00a0provocando un error contrario a la ley por parte de las autoridades \u00a0 \u00a0 \u00a0 \u00a0 \u00a0notariales y administrativas. \u00a0<\/p>\n<p>ANTECEDENTES \u00a0PROCESALES \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>7. Por \u00a0 \u00a0 \u00a0 \u00a0 \u00a0los hechos descritos, el 13 de diciembre de 2013 se llevaron a cabo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0las audiencias preliminares ante el Juzgado Primero Penal Municipal \u00a0 \u00a0 \u00a0 \u00a0 \u00a0con funci\u00f3n de Control de Garant\u00edas de Barranquilla2. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>8. En \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la misma diligencia, la Fiscal\u00eda General de la Naci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0imput\u00f3 a Agust\u00edn \u00a0 \u00a0 \u00a0 \u00a0 \u00a0M\u00e1rquez Solano, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en calidad de autor los punibles de estafa (art. 246) y fraude \u00a0 \u00a0 \u00a0 \u00a0 \u00a0procesal (art. 453). Cargos que no acept\u00f3. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>9. El \u00a0 \u00a0 \u00a0 \u00a0 \u00a07 de abril de 2014 fue presentado escrito de acusaci\u00f3n, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0realizando la respectiva audiencia el 30 de septiembre de esa misma \u00a0 \u00a0 \u00a0 \u00a0 \u00a0anualidad ante el Juzgado S\u00e9ptimo Penal del Circuito con \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Funci\u00f3n de Conocimiento de Barranquilla3. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>10. Por \u00a0 \u00a0 \u00a0 \u00a0 \u00a0su parte, la audiencia preparatoria se surti\u00f3 el d\u00eda 6 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de agosto de 20154. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>11. El \u00a0 \u00a0 \u00a0 \u00a0 \u00a0juicio oral se desarroll\u00f3 entre el 16 de marzo de 2016 y el \u00a0 \u00a0 \u00a0 \u00a0 \u00a013 de marzo de 20175. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>12. Mediante \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sentencia del 27 de marzo de 2017, M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Solano \u00a0 \u00a0 \u00a0 \u00a0 \u00a0fue condenado por los cargos imputados a la pena principal de 82 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0meses de prisi\u00f3n, multa de 200 SMLMV y a la pena accesoria de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0inhabilitaci\u00f3n para el ejercicio de derechos y funciones \u00a0 \u00a0 \u00a0 \u00a0 \u00a0p\u00fablicas por un t\u00e9rmino igual al de la pena \u00a0 \u00a0 \u00a0 \u00a0 \u00a0principal6. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>13. De la misma manera, se dispuso \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que el procesado no era acreedor del subrogado correspondiente a la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0suspensi\u00f3n condicional de la ejecuci\u00f3n de la pena, sin \u00a0 \u00a0 \u00a0 \u00a0 \u00a0embargo, le fue concedido el beneficio de prisi\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0domiciliaria, al cumplir con lo dispuesto en el art\u00edculo 23 y \u00a0 \u00a0 \u00a0 \u00a0 \u00a025 de la Ley 1709 de 2014, previo el pago de cauci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0prendaria por valor de 3 millones de pesos. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>14. La \u00a0 \u00a0 \u00a0 \u00a0 \u00a0defensa del procesado apel\u00f3 dicha determinaci\u00f3n, la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0cual fue confirmada en su totalidad por el Tribunal Superior del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Distrito Judicial de Barranquilla7. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>15. Contra \u00a0 \u00a0 \u00a0 \u00a0 \u00a0esa determinaci\u00f3n, la defensa de M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Solano \u00a0 \u00a0 \u00a0 \u00a0 \u00a0interpuso recurso extraordinario de casaci\u00f3n, allegando la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0respectiva demanda dentro del t\u00e9rmino legal8 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y sobre cuya admisibilidad se pronuncia ahora la Sala. \u00a0<\/p>\n<p>S\u00cdNTESIS \u00a0DE LA DEMANDA DE CASACI\u00d3N \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>16. Tras \u00a0 \u00a0 \u00a0 \u00a0 \u00a0identificar los sujetos procesales intervinientes, realizar una \u00a0 \u00a0 \u00a0 \u00a0 \u00a0s\u00edntesis de la sentencia que impugna, de los hechos materia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de juzgamiento y del transcurrir procesal, as\u00ed como citar \u00a0 \u00a0 \u00a0 \u00a0 \u00a0copiosa jurisprudencia y doctrina alrededor del principio in \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dubio pro reo, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el censor procedi\u00f3 a postular un \u00fanico cargo invocando \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la causal primera de casaci\u00f3n, dentro del cual alega la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0violaci\u00f3n directa de la ley sustancial. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>17. Sin \u00a0 \u00a0 \u00a0 \u00a0 \u00a0se\u00f1alar un error en espec\u00edfico alega, la sentencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0demandada desconoci\u00f3 el referido axioma, as\u00ed como los \u00a0 \u00a0 \u00a0 \u00a0 \u00a0art\u00edculos 7\u00b0, 9\u00b0 y 29 del C\u00f3digo Penal y como \u00a0 \u00a0 \u00a0 \u00a0 \u00a0consecuencia, aplic\u00f3 indebidamente los art\u00edculos 43, \u00a0 \u00a0 \u00a0 \u00a0 \u00a044, 52, 103, 104 n\u00fam. 4\u00b0, 246, 365, 372 y 453 n\u00fam. \u00a0 \u00a0 \u00a0 \u00a0 \u00a04\u00b0 del C\u00f3digo Penal. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>18. Reprocha, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la jurisdicci\u00f3n penal no era la \u00fanica competente para \u00a0 \u00a0 \u00a0 \u00a0 \u00a0conocer del caso, sino tambi\u00e9n la civil y comercial, tal como \u00a0 \u00a0 \u00a0 \u00a0 \u00a0lo establecen los art\u00edculos 1495 y s.s., 1502, 2079, 2085, \u00a0 \u00a0 \u00a0 \u00a0 \u00a02106, 2099, 2126 del C\u00f3digo Civil, 98 y s.s. del C\u00f3digo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de Comercio y 524 y s.s. del C\u00f3digo General del Proceso. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>19. No \u00a0 \u00a0 \u00a0 \u00a0 \u00a0se demostr\u00f3, continua, que M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Solano \u00a0 \u00a0 \u00a0 \u00a0 \u00a0desmejor\u00f3 el patrimonio social con la presunta venta de una \u00a0 \u00a0 \u00a0 \u00a0 \u00a0finca que no hizo parte de la sociedad, pues el bien no aparece \u00a0 \u00a0 \u00a0 \u00a0 \u00a0reportado dentro del objeto social de la misma, no distribuy\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0utilidades, \u201cni \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ven\u00eda cumpliendo con sus deberes; pues no aparece como prueba \u00a0 \u00a0 \u00a0 \u00a0 \u00a0un solo balance, documento, valores, o retenciones practicadas sobre \u00a0 \u00a0 \u00a0 \u00a0 \u00a0su seudomala administraci\u00f3n, ni una sola de esas pruebas, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0aparecen solicitadas, decretadas, practicadas en la instrucci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0o en el juicio oral.\u201d \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>20. Manifiesta \u00a0 \u00a0 \u00a0 \u00a0 \u00a0adem\u00e1s que \u201cla \u00a0 \u00a0 \u00a0 \u00a0 \u00a0notificaci\u00f3n por correo se entiende surtida \u00fanicamente \u00a0 \u00a0 \u00a0 \u00a0 \u00a0cuando el acto administrativo objeto de comunicaci\u00f3n ha sido \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en efecto recibido por el destinatario\u201d y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en el presente caso se surti\u00f3 de manera defectuosa por parte \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de la Superintendencia de Industria y Comercio. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>21. Afirma, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u201cse \u00a0 \u00a0 \u00a0 \u00a0 \u00a0logr\u00f3 probar que la se\u00f1ora HORTENSIA JIMENEZ despu\u00e9s \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de la remoci\u00f3n del cargo como socio gestor a mi patrocinado, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ella tambi\u00e9n actuaba como gestora para esas mismas calendas\u201d. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>22. Por \u00a0 \u00a0 \u00a0 \u00a0 \u00a0lo anterior, el censor solicita casar la sentencia recurrida, para \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que en su lugar se aplique el principio in \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dubio pro reo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0favor de su prohijado y como consecuencia se absuelva de los cargos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0formulados. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>23. En \u00a0 \u00a0 \u00a0 \u00a0 \u00a0atenci\u00f3n al art\u00edculo 184 inc. 2\u00b0 del C.P.P., la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0demanda de casaci\u00f3n resultar\u00e1 inadmitida cuando el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0demandante carezca de inter\u00e9s, omita se\u00f1alar la causal \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de casaci\u00f3n, no desarrolle de manera adecuada los cargos que \u00a0 \u00a0 \u00a0 \u00a0 \u00a0postula o cuando se muestra irrelevante para cumplir los prop\u00f3sitos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del recurso extraordinario. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>24. Reiteradamente ha se\u00f1alado \u00a0 \u00a0 \u00a0 \u00a0 \u00a0esta Sala que la demanda de casaci\u00f3n presentada debe cumplir \u00a0 \u00a0 \u00a0 \u00a0 \u00a0como m\u00ednimo con las siguientes condiciones de admisibilidad: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0i) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la acreditaci\u00f3n del agravio a los derechos o garant\u00edas \u00a0 \u00a0 \u00a0 \u00a0 \u00a0producidos con ocasi\u00f3n de la sentencia, ii) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el se\u00f1alamiento de la causal de casaci\u00f3n elegida con \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sujeci\u00f3n a los par\u00e1metros l\u00f3gicos, argumentales \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y de postulaci\u00f3n propios del motivo casacional postulado y, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0iii) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la determinaci\u00f3n de la necesidad del fallo de casaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0para alcanzar alguna de las finalidades se\u00f1aladas para el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0recurso (art. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0180 del C.P.P.)9. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>25. En consecuencia, el libelista \u00a0 \u00a0 \u00a0 \u00a0 \u00a0debe identificar con sumo cuidado el error que pretende denunciar, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0elegir precavidamente la causal o causales bajo las cuales lo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0encaminar\u00e1 \u00a0-previstas \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en el art\u00edculo 181 de la Ley 906 de 2004-, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0para finalmente desarrollar las censuras con impecable observancia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de los principios que rigen el presente recurso, demostrando su \u00a0 \u00a0 \u00a0 \u00a0 \u00a0trascendencia10, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0taxatividad11, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0no contradicci\u00f3n12, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0claridad y precisi\u00f3n13, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0as\u00ed como proponiendo un cargo jur\u00eddicamente completo14. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>26. Analizada \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la demanda presentada a la luz de los anteriores criterios, la Sala \u00a0 \u00a0 \u00a0 \u00a0 \u00a0proceder\u00e1 a inadmitirla, pues el demandante no sustenta alg\u00fan \u00a0 \u00a0 \u00a0 \u00a0 \u00a0error susceptible de estudiarse en esta sede, tampoco se vislumbra \u00a0 \u00a0 \u00a0 \u00a0 \u00a0alg\u00fan vicio dentro del proceso surtido, as\u00ed como \u00a0 \u00a0 \u00a0 \u00a0 \u00a0tampoco se contempla el cumplimiento de las finalidades previstas en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el art\u00edculo 180 del C.P.P., desde la \u00f3ptica oficiosa \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que cobija a esta Corporaci\u00f3n. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>27. El \u00a0 \u00a0 \u00a0 \u00a0 \u00a0recurrente postula un \u00fanico cargo dentro del cual alega la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0violaci\u00f3n directa de la ley sustancial, sin embargo, no s\u00f3lo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0pasa por alto el ejercicio de deconstrucci\u00f3n requerido en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sede casacional,15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0adem\u00e1s, propone un escrito reducido a un alegato de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0instancia, citando de manera desordenada y repetitiva jurisprudencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y doctrina alrededor del principio in \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dubio pro reo, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sin trascender realmente en alguna de sus disconformidades. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>28. A \u00a0 \u00a0 \u00a0 \u00a0 \u00a0modo de ver del recurrente, la sentencia del Tribunal incurri\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0adem\u00e1s en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0violaci\u00f3n directa de la ley sustancial, pese a ello reduce \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sus reproches a la menci\u00f3n superficial de la normativa que \u00a0 \u00a0 \u00a0 \u00a0 \u00a0considera vulnerada, sin profundizar, ni cumplir con el deber de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0desarrollar la censura bajo los par\u00e1metros l\u00f3gicos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0orientados a establecer de manera clara un error en la aplicaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del derecho con el fin de demostrar que el juzgador incurri\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en la falta de aplicaci\u00f3n, aplicaci\u00f3n indebida o \u00a0 \u00a0 \u00a0 \u00a0 \u00a0interpretaci\u00f3n err\u00f3nea de dichos preceptos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sustanciales.16 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>29. Su \u00a0 \u00a0 \u00a0 \u00a0 \u00a0disenso se centra en considerar que el Tribunal err\u00f3 al no \u00a0 \u00a0 \u00a0 \u00a0 \u00a0aplicar el principio in \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dubio pro reo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en favor de su defendido, pasando por alto los art\u00edculos 29 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Constitucional y 7\u00b0 de la Ley 906 de 2004. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>30. Frente \u00a0 \u00a0 \u00a0 \u00a0 \u00a0a ello, cabe precisar que en reiteradas ocasiones esta Corporaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ha manifestado que si tal cargo es el pretendido por el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0casacionista, este se encuentra en la obligaci\u00f3n de demostrar \u00a0 \u00a0 \u00a0 \u00a0 \u00a0con la trascendencia suficiente que los juzgadores inaplicaron las \u00a0 \u00a0 \u00a0 \u00a0 \u00a0reglas relativas a la presunci\u00f3n de inocencia, evidenciando \u00a0 \u00a0 \u00a0 \u00a0 \u00a0como m\u00ednimo, que reconocieron los presupuestos f\u00e1cticos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de duda respecto a la materialidad del delito o la responsabilidad \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del acusado, pero que finalmente no los tuvieron en cuenta. 17 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>31. En el caso bajo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0estudio, la demanda presentada por el censor, adem\u00e1s de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0transgredir los principios de claridad18 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y no contradicci\u00f3n19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0consustanciales al recurso extraordinario que presenta, en ning\u00fan \u00a0 \u00a0 \u00a0 \u00a0 \u00a0momento visibiliza el reconocimiento de alg\u00fan elemento \u00a0 \u00a0 \u00a0 \u00a0 \u00a0estructural de duda en favor de M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Solano. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>32. Contrario a lo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0pretendido por este y tras revisar la fundamentaci\u00f3n del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0fallo que recurre, se encuentra que de manera suficiente se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0expusieron los argumentos por los cuales consider\u00f3 probada \u00a0 \u00a0 \u00a0 \u00a0 \u00a0tanto la ocurrencia del hecho, como la responsabilidad del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0procesado: \u00a0<\/p>\n<p>\u201cPor \u00a0lo tanto, haciendo eco de lo dicho por la Fiscal\u00eda, de la \u00a0prueba documental y testimonial se puede llegar a la conclusi\u00f3n \u00a0que, el procesado sab\u00eda y conoc\u00eda lo que hac\u00eda, \u00a0hasta tal punto que, al estar en suspenso el tema administrativo, con \u00a0ocasi\u00f3n de uno de los recursos que impetr\u00f3 no pod\u00eda \u00a0hacer ning\u00fan movimiento de la sociedad familiar, no obstante, \u00a0traspas\u00f3 los inmuebles a \u00e9l mismo, es decir, \u00a0adecu\u00e1ndose a la descripci\u00f3n del FRAUDE PROCESAL, \u00a0siendo \u00e9ste el \u00fanico beneficiario de tal transacci\u00f3n \u00a0comercial, lo cual adem\u00e1s se aviene al concepto de ESTAFA que \u00a0hace el doctrinante ANT\u00d3N ONECA, para quien: \u201ces \u00a0la conducta enga\u00f1osa, con \u00e1nimo de lucro injusto, \u00a0propio o ajeno, que, determinando un error en una o varias personas, \u00a0les induce a realizar acto de disposici\u00f3n, consecuencia del \u00a0cual es un perjuicio en su patrimonio\u201d. \u00a0Siendo que, sobre \u00e9ste \u00faltimo reato, a voces de lo que \u00a0ha sostenido la Honorable Corte Suprema de Justicia lo que sanciona \u00a0el derecho penal es el \u201cenga\u00f1o \u00a0como artificio para defraudar patrimonialmente a otro en el contexto \u00a0de la relaci\u00f3n social, prejur\u00eddica y dial\u00e9ctica \u00a0que el derecho penal protege\u201d. \u00a0Por todo, se requiere una protecci\u00f3n penal, al margen de la \u00a0civil, pues hubo un direccionamiento del dolo penal al injusto. \u00a0<\/p>\n<p>De \u00a0forma tal que el sujeto agente aqu\u00ed conoc\u00eda la \u00a0antijuridicidad de su conducta, ten\u00eda conciencia de ella, es \u00a0decir, del da\u00f1o real, potencial causado. \u00a0<\/p>\n<p>De \u00a0modo que, no hay duda que se est\u00e1 en presencia de los \u00a0elementos de la ESTAFA, ya que, hubo enga\u00f1o, como la \u00a0simulaci\u00f3n de ser a\u00fan el gerente y representante legal, \u00a0falt\u00f3 a la verdad, desconfigur\u00f3 la realidad; para tener \u00a0disposici\u00f3n patrimonial que caus\u00f3 la disminuci\u00f3n \u00a0de las propiedades de las v\u00edctimas, que no requer\u00eda \u00a0expresamente la entrega de la cosa, pues un sector de la doctrina, \u00a0entre ellos, GRIMA LIZANDRA y J.A. CHOCL\u00c1N MONTALVO, consiste \u00a0en: \u201cla \u00a0salida del patrimonio de un bien\u201d \u00a0o \u201cla salida \u00a0de un elemento patrimonial de la esfera de dominio de su titular, \u00a0entrando il\u00edcitamente en la esfera de dominio del autor del \u00a0delito\u201d, \u00a0todo, con perjuicio y \u00e1nimo de lucro por parte del procesado \u00a0en este caso del detrimento de los intereses de su propia familia. \u00a0<\/p>\n<p>Por \u00a0todo, las conductas de ESTAFA y FRAUDE PROCESAL s\u00ed fueron \u00a0cometidas por el procesado, al haber obtenido provecho il\u00edcito \u00a0para s\u00ed e induciendo en error a un servidor p\u00fablico por \u00a0medio de artificios y enga\u00f1os abrog\u00e1ndose una calidad \u00a0de representaci\u00f3n con la cual ya no contaba al momento de la \u00a0venta de los bienes inmuebles\u201d20. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>33. Adem\u00e1s, el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0expediente devela que el defensor no formul\u00f3 en el momento \u00a0 \u00a0 \u00a0 \u00a0 \u00a0procesal pertinente la presunta vulneraci\u00f3n que hasta esta \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sede alega, pues sus argumentos no concurren ni siquiera en la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0apelaci\u00f3n presentada ante el fallador de instancia. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>34. Lo que si se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0encuentra resuelto, es el reproche que ahora propone respecto a la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0competencia del presente litigio, pues argumenta que realmente su \u00a0 \u00a0 \u00a0 \u00a0 \u00a0conocimiento le correspond\u00eda a la jurisdicci\u00f3n civil. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Frente a ello el Tribunal concluy\u00f3: \u00a0<\/p>\n<p>\u201cAs\u00ed \u00a0las cosas, contrario a lo afirmado por la bancada de la defensa, la \u00a0conducta desplegada por el procesado si trasciende a las esferas del \u00a0derecho penal y lejos est\u00e1 de ser un asunto netamente civil, \u00a0cuyo dolo implica que una conducta il\u00edcita de uno de los \u00a0contratantes est\u00e1 orientada a inducir en error al otro, \u00a0mediante maniobras fraudulentas, enga\u00f1os, mentiras, trampas o \u00a0artificios, a fin de sorprender a la v\u00edctima y provocar su \u00a0adhesi\u00f3n al negocio jur\u00eddico o a determinadas \u00a0condiciones del mismo. \u00a0<\/p>\n<p>El \u00a0dolo civil debe probarse por parte de quien lo alega, pues este solo \u00a0se presume (presunci\u00f3n legal) en los casos expl\u00edcitamente \u00a0se\u00f1alados en la ley. Algunos de estos son: Art. 1025 numeral \u00a05\u00b0 C\u00f3digo Civil: detenci\u00f3n u ocultaci\u00f3n del \u00a0testamento del difunto; Art. 2284 C\u00f3digo Civil: dolo en la \u00a0apuesta; Art. 1058 C\u00f3digo de Comercio: falta de informaci\u00f3n \u00a0sobre enfermedad grave del asegurado\u201d \u00a021. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>35. Por \u00a0 \u00a0 \u00a0 \u00a0 \u00a0otro lado, de manera desordenada, afirma no es cierto que M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Solano \u00a0 \u00a0 \u00a0 \u00a0 \u00a0desmejor\u00f3 el patrimonio social con la presunta venta de una \u00a0 \u00a0 \u00a0 \u00a0 \u00a0finca que no hizo parte de la sociedad, pues el bien no aparece \u00a0 \u00a0 \u00a0 \u00a0 \u00a0reportado dentro del objeto social de la misma, ni distribuy\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0utilidades. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>36. Tambi\u00e9n, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que la notificaci\u00f3n en la cual se le informaba ya no era el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0representante legal de la sociedad M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jim\u00e9nez &amp; CIA S. en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0C., en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el presente caso se surti\u00f3 de manera defectuosa por parte de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la Superintendencia de Industria y Comercio. \u00a0<\/p>\n<p>37. Y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0por \u00faltimo manifiesta que se logr\u00f3 probar que la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0se\u00f1ora Hortensia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jim\u00e9nez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0tambi\u00e9n actuaba como gestora para la misma fecha en la cual \u00a0 \u00a0 \u00a0 \u00a0 \u00a0fue eliminado del cargo su defendido. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>38. Los anteriores \u00a0 \u00a0 \u00a0 \u00a0 \u00a0argumentos \u00fanicamente evidencian que lo pretendido por el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0censor realmente es exponer que los elementos de juicio incorporados \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en el transcurrir procesal, y que fueron resueltos en las instancias \u00a0 \u00a0 \u00a0 \u00a0 \u00a0extensamente, as\u00ed como el elemento procedimental que \u00a0 \u00a0 \u00a0 \u00a0 \u00a0menciona, se muestran insuficientes para demostrar la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0responsabilidad de M\u00e1rquez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Solano \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en grado suficiente para proferir condena. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>39. Sin embargo, tal \u00a0 \u00a0 \u00a0 \u00a0 \u00a0reproche corresponde a una apreciaci\u00f3n subjetiva del mismo, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que adem\u00e1s de no encontrar camino dentro de la violaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0directa de la ley sustancial denunciada, la forma en la cual decidi\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0postularlo resulta propio de un discurso de instancias. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>40. En \u00a0 \u00a0 \u00a0 \u00a0 \u00a0s\u00edntesis, los planteamientos propuestos por el demandante se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0apartan del discurso jur\u00eddico adecuado en sede casacional, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0pues se acotan en proponer su teor\u00eda del caso por sobre la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0estructura de acierto y legalidad que cobija las sentencias que \u00a0 \u00a0 \u00a0 \u00a0 \u00a0recurre, pasando por alto que su disentimiento en manera alguna \u00a0 \u00a0 \u00a0 \u00a0 \u00a0satisface las exigencias para estudiar de fondo tal reproche. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>41. Tampoco se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0encuentra por parte de esta Sala, que la decisi\u00f3n cuestionada \u00a0 \u00a0 \u00a0 \u00a0 \u00a0haya incurrido en alg\u00fan yerro constitutivo de violaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0directa o indirecta de la ley sustancial, as\u00ed como tampoco se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0percibe alguna situaci\u00f3n an\u00f3mala en perjuicio de las \u00a0 \u00a0 \u00a0 \u00a0 \u00a0garant\u00edas del proceso surtido que justifique la intervenci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de esta Corporaci\u00f3n en el ejercicio de la facultad oficiosa \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que le asiste. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>42. Como consecuencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de lo anterior, se dispondr\u00e1 la INADMISI\u00d3N \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del libelo como lo ordena el art\u00edculo 184, inciso 2\u00b0, de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la Ley 906 de 2004, determinaci\u00f3n contra la cual procede el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0mecanismo de insistencia de acuerdo con los lineamientos se\u00f1alados \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en el auto del 12 de diciembre de 2005, radicado 24.322. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la CORTE \u00a0SUPREMA DE JUSTICIA, SALA DE CASACI\u00d3N PENAL, \u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>1\u00ba. \u00a0NO ADMITIR \u00a0la demanda de casaci\u00f3n interpuesta por la defensa de Agust\u00edn \u00a0M\u00e1rquez Solano, \u00a0por las razones expuestas en precedencia. \u00a0<\/p>\n<p>2\u00ba. \u00a0ADVERTIR \u00a0que, de conformidad con lo dispuesto en el art. 184 inc. 2\u00ba del \u00a0C.P.P., contra la presente decisi\u00f3n procede el mecanismo de \u00a0insistencia, con atenci\u00f3n de las reglas definidas \u00a0jurisprudencialmente por la Sala. \u00a0<\/p>\n<p>Notif\u00edquese, \u00a0c\u00famplase y devu\u00e9lvase al Tribunal de origen. \u00a0<\/p>\n<p>GERSON \u00a0CHAVERRA CASTRO \u00a0<\/p>\n<p>JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>DIEGO \u00a0EUGENIO CORREDOR BELTR\u00c1N \u00a0<\/p>\n<p>LUIS \u00a0ANTONIO HERN\u00c1NDEZ BARBOSA \u00a0<\/p>\n<p>FABIO \u00a0OSPITIA GARZ\u00d3N \u00a0<\/p>\n<p>HUGO \u00a0QUINTERO BERNATE \u00a0<\/p>\n<p>NUBIA YOLANDA \u00a0NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0No 2. Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0222- 225; Cuaderno del Tribunal No 2. Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a019-20. \u00a0<\/p>\n<p>2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0No 1. Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a032. \u00a0<\/p>\n<p>3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0No 1. Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a054-58 y 92. \u00a0<\/p>\n<p>4 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0No 1. Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0179. \u00a0<\/p>\n<p>5 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0No 1. Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0306 \u2013 Cuaderno No 2. Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a037-187. \u00a0<\/p>\n<p>6 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0No 2. Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0203-225. \u00a0<\/p>\n<p>7 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del Tribunal No 2. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a019-39. \u00a0<\/p>\n<p>8 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Demanda \u00a0 \u00a0 \u00a0 \u00a0 \u00a0presentada el d\u00eda 30 de abril de 2018. \u00a0<\/p>\n<p>9 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Entre otros Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-AP, 13 jun. 2007, Rad. 27.537; AP, 25 jul. 2007, Rad. 27.810 y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0AP, \u00a0 \u00a0 \u00a0 \u00a0 \u00a002 oct. 2019, Rad. 53.102. \u00a0<\/p>\n<p>10 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-SP, 30 abr. 2019, Rad. 50.996. \u00a0<\/p>\n<p>11 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-AP, \u00a0 \u00a0 \u00a0 \u00a0 \u00a011 mar. 2020, Rad. 57.101. \u00a0<\/p>\n<p>12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-SP, 12 mar. 2014, Rad. 43.317. \u00a0<\/p>\n<p>13 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-AP, 30 sep. 2020, Rad. 54.050. \u00a0<\/p>\n<p>14 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-SP, 04 abr. 2018, Rad. 50.990. \u00a0<\/p>\n<p>15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-AP, 30 mar. 2016, rad. 42.397. \u00a0<\/p>\n<p>16 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-AP. \u00a0 \u00a0 \u00a0 \u00a0 \u00a006 may. 2020. Rad. \u00a0 \u00a0 \u00a0 \u00a0 \u00a056.235. \u00a0<\/p>\n<p>17 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-AP. \u00a0 \u00a0 \u00a0 \u00a0 \u00a06 ago. 2019. Rad. 50.994 y AP- 30 sep. 2020. Rad. 51.590, entre \u00a0 \u00a0 \u00a0 \u00a0 \u00a0otros. \u00a0<\/p>\n<p>18 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-AP. \u00a0 \u00a0 \u00a0 \u00a0 \u00a030 sep. 2020, Rad. 54.050. \u00a0<\/p>\n<p>19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ-SP. \u00a0 \u00a0 \u00a0 \u00a0 \u00a012 mar. 2014, Rad. 43.317. \u00a0<\/p>\n<p>20 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del Tribunal No 2. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a033-34. \u00a0<\/p>\n<p>21 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del Tribunal No 2. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Fl. \u00a0 \u00a0 \u00a0 \u00a0 \u00a031. \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0 Magistrado \u00a0Ponente \u00a0 AP5617-2021 \u00a0 Radicaci\u00f3n \u00a0N\u00b0 52972 \u00a0 Aprobado \u00a0acta No 307 \u00a0 Bogot\u00e1, \u00a0D. C., veinticuatro (24) de noviembre de dos mil veintiuno (2021). \u00a0 VISTOS \u00a0 La \u00a0Corte decide sobre la admisibilidad de la demanda de casaci\u00f3n \u00a0presentada por el defensor de Agust\u00edn [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,42],"tags":[],"class_list":["post-60280","post","type-post","status-publish","format-standard","hentry","category-30","category-noviembre"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/60280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=60280"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/60280\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=60280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=60280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=60280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}