{"id":5850,"date":"2023-09-08T16:23:52","date_gmt":"2023-09-08T16:23:52","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1616718-07-02\/"},"modified":"2023-09-08T16:23:52","modified_gmt":"2023-09-08T16:23:52","slug":"1616718-07-02","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1616718-07-02\/","title":{"rendered":"16167(18-07-02)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 16167 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Magistrado ponente: \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Nilson Pinilla Pinilla \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Aprobado Acta N\u00b0 082 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D. \u00a0C., julio dieciocho (18) de dos \u00a0mil dos (2002). \u00a0\u00a0<\/p>\n<p>ASUNTO \u00a0<\/p>\n<p>Se decide la casaci\u00f3n interpuesta en defensa \u00a0de \u00a0HERN\u00c1N \u00a0AUGUSTO \u00a0ZAPATA \u00a0OSORIO, \u00a0contra \u00a0el \u00a0fallo \u00a0por \u00a0medio del cual el \u00a0Tribunal \u00a0Nacional \u00a0confirm\u00f3 \u00a0el \u00a0dictado por un Juzgado Regional de Medell\u00edn, \u00a0que \u00a0lo \u00a0conden\u00f3 \u00a0por \u00a0secuestro \u00a0extorsivo, \u00a0porte ilegal de armas de fuego de \u00a0defensa personal y hurto calificado agravado. \u00a0\u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>Hacia las 2:30 de la tarde del 5 de diciembre \u00a0de \u00a01994, \u00a0cuando \u00a0Jos\u00e9 \u00a0William \u00a0Rojas \u00a0se \u00a0movilizaba \u00a0en \u00a0un veh\u00edculo de su \u00a0propiedad \u00a0por \u00a0la \u00a0Avenida del Ferrocarril de Medell\u00edn, fue interceptado antes \u00a0de \u00a0llegar \u00a0a la calle Barranquilla por un individuo que tras intimidarlo con el \u00a0arma \u00a0de \u00a0fuego \u00a0que portaba, le orden\u00f3 seguir hasta el sitio donde esperaba un \u00a0segundo \u00a0asaltante, \u00a0que \u00a0se \u00a0llev\u00f3 \u00a0el carro. De inmediato aqu\u00e9l condujo a la \u00a0v\u00edctima \u00a0en taxi hasta el barrio Zamora y lo dej\u00f3 en un inmueble al cuidado de \u00a0un tercero, a quien le entreg\u00f3 el arma para que lo vigilara. \u00a0\u00a0<\/p>\n<p>Despu\u00e9s este \u00faltimo le exigi\u00f3 un cheque por \u00a0$ \u00a01.000.000 \u00a0para \u00a0entregarle el veh\u00edculo, pero como no lo pudieron cobrar, el \u00a0retenido \u00a0logr\u00f3 \u00a0convencerlo de que su esposa pod\u00eda conseguir el dinero; cerca \u00a0de \u00a0las \u00a0seis \u00a0de \u00a0la \u00a0tarde \u00a0salieron \u00a0a llamarla y acordaron encontrarse en la \u00a0agencia \u00a0de \u00a0Conavi \u00a0del \u00a0barrio \u00a0Bel\u00e9n, \u00a0donde \u00a0fue capturado el retenedor, de \u00a0nombre HERN\u00c1N AUGUSTO ZAPATA OSORIO. \u00a0\u00a0<\/p>\n<p>ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>Inici\u00f3 investigaci\u00f3n la Fiscal\u00eda Regional, \u00a0pero \u00a0no \u00a0fue posible la vinculaci\u00f3n del capturado mediante indagatoria, ya que \u00a0en \u00a0extra\u00f1as \u00a0circunstancias \u00a0fue dejado en libertad, expidi\u00e9ndose copias para \u00a0que \u00a0 la \u00a0 Fiscal\u00eda \u00a0 y \u00a0 la \u00a0 Procuradur\u00eda \u00a0adelantaran \u00a0la \u00a0correspondientes \u00a0averiguaciones. \u00a0Se \u00a0hizo \u00a0as\u00ed \u00a0necesaria \u00a0la \u00a0declaraci\u00f3n de persona ausente, \u00a0previo emplazamiento. \u00a0\u00a0<\/p>\n<p>El instructor le impuso detenci\u00f3n preventiva \u00a0el \u00a01\u00b0 \u00a0de \u00a0marzo \u00a0de 1996 (fs. 70 y Ss. cd. 1) y reiter\u00f3 la orden de captura, \u00a0que \u00a0se \u00a0hizo efectiva el 24 del mismo mes, recibi\u00e9ndosele indagatoria. Cerrada \u00a0la \u00a0instrucci\u00f3n, \u00a0el \u00a014 \u00a0de \u00a0agosto de 1996 se impuso a HERN\u00c1N AUGUSTO ZAPATA \u00a0OSORIO \u00a0resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n, \u00a0por \u00a0los \u00a0delitos \u00a0de \u00a0secuestro extorsivo \u00a0agravado, \u00a0porte \u00a0ilegal de arma de fuego de defensa personal y hurto calificado \u00a0agravado \u00a0(fs. \u00a0227 \u00a0y \u00a0Ss. \u00a0ib.), \u00a0enjuiciamiento \u00a0apelado \u00a0por \u00a0el procesado y \u00a0confirmado \u00a0por \u00a0la \u00a0Fiscal\u00eda Delegada ante el Tribunal Nacional el 24 de julio \u00a0de \u00a01997 \u00a0(fs. \u00a04 y Ss. cd. respectivo), aclarando que la agravaci\u00f3n no procede \u00a0frente al secuestro extorsivo, sino sobre el hurto. \u00a0\u00a0<\/p>\n<p>Adelant\u00f3 \u00a0el \u00a0juicio \u00a0un Juzgado Regional de \u00a0Medell\u00edn \u00a0que, previa citaci\u00f3n para sentencia, conden\u00f3 el 28 de septiembre de \u00a01998 \u00a0al \u00a0procesado, por los delitos de la acusaci\u00f3n, imponi\u00e9ndole 28 a\u00f1os de \u00a0prisi\u00f3n, \u00a0el \u00a0equivalente \u00a0de 120 salarios m\u00ednimos legales mensuales de multa, \u00a010 \u00a0a\u00f1os \u00a0de interdicci\u00f3n de derecho y funciones p\u00fablicas y la obligaci\u00f3n de \u00a0indemnizar \u00a0los \u00a0respectivos \u00a0perjuicios \u00a0(fs. \u00a0373 y Ss.), fallo apelado por el \u00a0sindicado \u00a0y \u00a0su \u00a0defensor \u00a0y \u00a0confirmado el 29 de enero de 1999 por el Tribunal \u00a0Nacional \u00a0(fs. \u00a04 \u00a0y \u00a0Ss. cd. Trib.), mediante sentencia as\u00ed mismo impugnada en \u00a0casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>Invocando \u00a0la \u00a0causal \u00a0tercera \u00a0de casaci\u00f3n, \u00a0aduce \u00a0el \u00a0defensor \u00a0falta \u00a0de \u00a0competencia de la justicia regional, teniendo en \u00a0cuenta \u00a0 que \u00a0por \u00a0expresa \u00a0disposici\u00f3n \u00a0del \u00a0art\u00edculo \u00a071-5 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0solamente pod\u00eda conocer del delito de secuestro extorsivo \u00a0si \u00a0concurr\u00eda \u00a0alguna de las circunstancias previstas en los numerales 6\u00b0, 8\u00b0 \u00a0o \u00a012\u00b0 \u00a0del \u00a0art\u00edculo \u00a03\u00b0 de la ley 40 de 1993, pero no del presente caso, ya \u00a0que \u00a0el \u00a0sujeto pasivo del delito no revest\u00eda la cualificaci\u00f3n contemplada por \u00a0esa preceptiva, ni el hecho fue cometido con fines terroristas. \u00a0\u00a0<\/p>\n<p>Recuerda \u00a0adem\u00e1s \u00a0que \u00a0el art\u00edculo 29 de la \u00a0Constituci\u00f3n \u00a0 dispone \u00a0que \u00a0el \u00a0debido \u00a0proceso \u00a0se \u00a0aplicar\u00e1 \u00a0en \u00a0todas \u00a0las \u00a0actuaciones \u00a0judiciales \u00a0o \u00a0administrativas \u00a0y que nadie podr\u00e1 ser juzgado sino \u00a0conforme \u00a0a \u00a0las \u00a0leyes \u00a0preexistentes \u00a0al \u00a0acto \u00a0que se le imputa y por el juez \u00a0competente, \u00a0de \u00a0modo \u00a0que \u00a0el vicio denunciado afecta la legalidad del proceso, \u00a0desde \u00a0el \u00a0momento \u00a0que \u00a0la \u00a0Fiscal\u00eda \u00a0Regional asumi\u00f3 competencia, por lo que \u00a0solicita casar la sentencia y declarar la nulidad de lo actuado. \u00a0\u00a0<\/p>\n<p>CONCEPTO DEL MINISTERIO P\u00daBLICO \u00a0<\/p>\n<p>Indica \u00a0el \u00a0Procurador Tercero Delegado en lo \u00a0Penal, \u00a0que \u00a0la \u00a0competencia \u00a0de \u00a0la \u00a0Justicia \u00a0Regional \u00a0qued\u00f3 suficientemente \u00a0decantada \u00a0en \u00a0la \u00a0sentencia \u00a0de \u00a0segunda instancia, que de manera preferente se \u00a0ocup\u00f3 \u00a0del \u00a0tema, \u00a0ante \u00a0la insistencia del recurrente para que se decretara la \u00a0nulidad \u00a0de \u00a0la \u00a0actuaci\u00f3n, descart\u00e1ndose al ratificarse la configuraci\u00f3n del \u00a0delito de secuestro extorsivo. \u00a0\u00a0<\/p>\n<p>Destaca que el desacierto del casacionista se \u00a0ubica \u00a0en \u00a0que para conocer la Justicia Regional del secuestro extorsivo, deb\u00eda \u00a0concurrir \u00a0alguna \u00a0de \u00a0las \u00a0circunstancias indicadas en los numerales 6\u00b0, 8\u00b0 o \u00a012\u00b0 \u00a0del \u00a0art\u00edculo \u00a03\u00b0 \u00a0de \u00a0la \u00a0ley \u00a040 \u00a0de \u00a01993, sin tomar en cuenta que la \u00a0disyunci\u00f3n \u00a0\u201co\u201d \u00a0que separa las palabras extorsivo y agravado, al contrario \u00a0de \u00a0lo demandado, est\u00e1 indicando que tiene competencia en cualquiera de los dos \u00a0eventos, \u00a0con \u00a0la \u00a0condici\u00f3n \u00a0de \u00a0que \u00a0en \u00a0el \u00a0agravado concurra alguna de esas \u00a0circunstancias, \u00a0es decir, conoce de todos los delitos de secuestro extorsivo, y \u00a0los \u00a0 \u00a0 de \u00a0 \u00a0 secuestro \u00a0 \u00a0 agravado \u00a0 \u00a0cuando \u00a0 \u00a0medie \u00a0 \u00a0alguna \u00a0 \u00a0de \u00a0 \u00a0esas \u00a0circunstancias. \u00a0\u00a0<\/p>\n<p>Es \u00a0probable \u00a0que el libelista se haya guiado \u00a0por \u00a0la \u00a0decisi\u00f3n \u00a0del \u00a0Fiscal, \u00a0que \u00a0anunci\u00f3 \u00a0como agravante del secuestro la \u00a0contemplada \u00a0en \u00a0el \u00a0art\u00edculo \u00a0372 \u00a0del anterior C\u00f3digo Penal, pero la segunda \u00a0instancia \u00a0 al \u00a0 revisar \u00a0la \u00a0resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n \u00a0dej\u00f3 \u00a0en \u00a0claro \u00a0que \u00a0correspond\u00eda al delito de hurto calificado. \u00a0\u00a0<\/p>\n<p>Advierte as\u00ed el Delegado que la sentencia fue \u00a0dictada \u00a0por \u00a0quien \u00a0ten\u00eda \u00a0facultad \u00a0para \u00a0proferirla, \u00a0por \u00a0lo cual no existe \u00a0violaci\u00f3n \u00a0de \u00a0principio alguno. Sin hallar necesario entrar en consideraciones \u00a0adicionales, solicita de la Corte no casar la sentencia impugnada. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE \u00a0LA \u00a0CORTE \u00a0\u00a0<\/p>\n<p>1.- \u00a0Para \u00a0la \u00a0\u00e9poca \u00a0de \u00a0los hechos, ten\u00eda \u00a0establecido \u00a0el \u00a0art\u00edculo \u00a071-5 del decreto 2700 de 1991, modificado por el 9\u00b0 \u00a0de \u00a0la \u00a0ley \u00a081 \u00a0de \u00a01993, que los jueces regionales conoc\u00edan de los delitos de \u00a0\u201csecuestro \u00a0extorsivo o agravado en virtud de los numerales 6, 8 o 12 del art. \u00a03\u00b0 \u00a0de la ley 40 de 1993\u201d, correspondiendo la primera modalidad a la conducta \u00a0entonces \u00a0prevista \u00a0en \u00a0el art\u00edculo 268 del decreto 100 de 1980, modificado por \u00a0el \u00a0art\u00edculo \u00a01\u00b0 \u00a0de \u00a0la \u00a0citada \u00a0ley, \u00a0en \u00a0tanto que la segunda representa la \u00a0concurrencia \u00a0de \u00a0circunstancias \u00a0de \u00a0agravaci\u00f3n en el secuestro; el legislador \u00a0utiliz\u00f3 \u00a0la \u00a0part\u00edcula disyuntiva \u201co\u201d, para indicar que la competencia del \u00a0regional \u00a0no \u00a0est\u00e1 \u00a0exclusivamente \u00a0referida a esas formas de agravaci\u00f3n, pues \u00a0comprende todo caso de secuestro extorsivo. \u00a0\u00a0<\/p>\n<p>Esta interpretaci\u00f3n obedece al criterio desde \u00a0entonces \u00a0reiterado \u00a0por \u00a0la \u00a0Sala, \u00a0que \u00a0al \u00a0resolver conflictos de competencia \u00a0relacionados con el tema en discusi\u00f3n, precis\u00f3: \u00a0\u00a0<\/p>\n<p>\u201cLos jueces regionales conocen de dos clases \u00a0de \u00a0secuestro: \u00a0a) Del secuestro extorsivo sin necesidad de que concurra ninguna \u00a0circunstancia \u00a0espec\u00edfica \u00a0de \u00a0agravaci\u00f3n; \u00a0y b) del simple cuando se presente \u00a0cualquiera \u00a0 de \u00a0 las \u00a0 circunstancias \u00a0 citadas \u00a0en \u00a0el \u00a0art\u00edculo \u00a071 \u00a0numeral \u00a05\u00b0. \u00a0\u00a0<\/p>\n<p>Los jueces penales del circuito s\u00f3lo conocen \u00a0del \u00a0 delito \u00a0 de \u00a0 secuestro \u00a0 simple, \u00a0 cuando \u00a0no \u00a0concurra \u00a0ninguna \u00a0de \u00a0las \u00a0circunstancias de agravaci\u00f3n antes se\u00f1aladas. \u00a0\u00a0<\/p>\n<p>No se pase por alto que de acuerdo con la ley \u00a040 \u00a0de \u00a01993\u2026, \u00a0art\u00edculo \u00a03\u00b0, \u00a0existen \u00a0agravantes \u00a0tanto \u00a0para el secuestro \u00a0extorsivo \u00a0 que \u00a0 define \u00a0 en \u00a0 su \u00a0art\u00edculo \u00a01\u00b0, \u00a0como \u00a0respecto \u00a0del \u00a0simple \u00a0(par\u00e1grafo), que tipifica en el art\u00edculo 2\u00b0. \u00a0\u00a0<\/p>\n<p>En este sentido y con la precisi\u00f3n de que la \u00a0\u201co\u201d \u00a0que \u00a0utiliza \u00a0el \u00a0referido \u00a0numeral 5\u00b0 de la ley 81 es disyuntiva y no \u00a0copulativa \u00a0se resolver\u00e1 el conflicto.\u201d (Auto de marzo 3 de 1994, rad. 9.149, \u00a0M. P. Guillermo Duque Ruiz). \u00a0\u00a0<\/p>\n<p>\u201c\u2026 es preciso concluir que el legislador \u00a0quiso \u00a0en \u00a0el \u00a0art. \u00a09-5 \u00a0de la ley 81 de 1993, otorgar competencia a los jueces \u00a0regionales, \u00a0para conocer de aquellos delitos de secuestro que ofenden con mayor \u00a0intensidad \u00a0el \u00a0bien \u00a0jur\u00eddico protegido por la norma y que conllevan una mayor \u00a0punibilidad. \u00a0Por \u00a0eso \u00a0en \u00a0dicho precepto al estatuir que los jueces regionales \u00a0conocen \u00a0\u2018\u2026 De los delitos \u00a0de \u00a0secuestro \u00a0extorsivo o agravado en virtud de los numerales 6\u00b0, 8\u00b0 o 12 del \u00a0art. \u00a0 3\u00b0 \u00a0 de \u00a0 la \u00a0ley \u00a040 \u00a0de \u00a01993\u2019, \u00a0les est\u00e1 otorgando a dichos funcionarios competencia para juzgar \u00a0no \u00a0solo \u00a0el \u00a0secuestro extorsivo, sino adem\u00e1s el secuestro simple agravado por \u00a0las \u00a0tres \u00a0circunstancias \u00a0espec\u00edficas \u00a0de \u00a0mayor \u00a0punibilidad \u00a0a \u00a0que alude la \u00a0norma. \u00a0\u00a0<\/p>\n<p>En \u00a0su \u00a0sentido \u00a0natural, obvio y de l\u00f3gica \u00a0jur\u00eddica, \u00a0la \u00a0letra \u00a0\u201co\u201d \u00a0debe entenderse como una conjunci\u00f3n disyuntiva, \u00a0que \u00a0diferencia \u00a0y \u00a0separa \u00a0los \u00a0dos \u00a0conceptos del secuestro extorsivo y el del \u00a0secuestro \u00a0simple \u00a0agravado\u2026\u201d \u00a0(Auto \u00a0de \u00a0marzo 3 de 1994, rad. 9.137, M. P. \u00a0Jorge Carre\u00f1o Luengas). \u00a0\u00a0<\/p>\n<p>2.- \u00a0El \u00a0cuanto \u00a0se \u00a0alude en la demanda a la \u00a0exigencia \u00a0del \u00a0art\u00edculo 29 de la Carta, de ser juzgado \u201cante juez o tribunal \u00a0competente\u201d, \u00a0basta recordar que la Corte Constitucional declar\u00f3 exequible el \u00a0numeral \u00a05\u00b0 del art\u00edculo 71 del C\u00f3digo de Procedimiento Penal, modificado por \u00a0el \u00a0art\u00edculo \u00a09\u00b0 de la ley 81 de 1993, mediante sentencia C-040 de 1997 (M. P. \u00a0Antonio Barrera Carbonell), precisando: \u00a0\u00a0<\/p>\n<p>\u201cLa \u00a0 competencia \u00a0ha \u00a0sido \u00a0com\u00fanmente \u00a0concebida \u00a0 como \u00a0la \u00a0porci\u00f3n, \u00a0la \u00a0cantidad, \u00a0la \u00a0medida \u00a0o \u00a0el \u00a0grado \u00a0de \u00a0la \u00a0jurisdicci\u00f3n \u00a0 que \u00a0 corresponde \u00a0 a \u00a0 cada \u00a0 juez \u00a0 o \u00a0tribunal, \u00a0mediante \u00a0la \u00a0determinaci\u00f3n \u00a0 de \u00a0 los \u00a0 asuntos \u00a0 que \u00a0 le \u00a0corresponde \u00a0conocer, \u00a0atendidos \u00a0determinados factores (materia, cuant\u00eda, lugar, etc). \u00a0\u00a0<\/p>\n<p>Conforme al art\u00edculo 29 de la Constituci\u00f3n, \u00a0elemento \u00a0integrante \u00a0del debido proceso penal lo constituye la instituci\u00f3n del \u00a0juez \u00a0 o \u00a0 tribunal \u00a0 competente \u00a0que \u00a0debe \u00a0efectuar \u00a0la \u00a0investigaci\u00f3n \u00a0y \u00a0el \u00a0juzgamiento, \u00a0observando \u00a0la \u00a0plenitud \u00a0de las formas propias de cada juicio. En \u00a0consecuencia, \u00a0corresponde \u00a0al legislador determinar los funcionarios judiciales \u00a0a \u00a0quienes \u00a0se \u00a0les \u00a0encomienda el ejercicio de la funci\u00f3n jurisdiccional y los \u00a0asuntos \u00a0que \u00a0son \u00a0de \u00a0su conocimiento, con arreglo a los diferentes factores de \u00a0competencia.\u201d \u00a0\u00a0<\/p>\n<p>Por \u00a0tanto, resulta infundado el reproche por \u00a0nulidad, \u00a0 derivada \u00a0 de \u00a0 la \u00a0alegada \u00a0falta \u00a0de \u00a0competencia \u00a0de \u00a0la \u00a0justicia \u00a0regional. \u00a0\u00a0<\/p>\n<p>3.- Conviene recordar que, frente a decisiones \u00a0como \u00a0\u00e9sta, \u00a0la \u00a0Sala ha se\u00f1alado que el ajuste punitivo que pudiere derivarse \u00a0de \u00a0la \u00a0aplicaci\u00f3n por favorabilidad de los preceptos respectivos de la ley 599 \u00a0de \u00a02000, \u00a0debe \u00a0ser \u00a0considerado \u00a0por \u00a0el correspondiente Juez de Ejecuci\u00f3n de \u00a0Penas y Medidas de Seguridad (art. 79-7 L. 600 de 2000). \u00a0\u00a0<\/p>\n<p>4.- \u00a0De \u00a0otra \u00a0parte, como no se sustituye el \u00a0fallo \u00a0 contra \u00a0 el \u00a0 cual \u00a0va \u00a0dirigida \u00a0la \u00a0demanda, \u00a0esta \u00a0providencia \u00a0queda \u00a0ejecutoriada \u00a0el d\u00eda en que es suscrita (art. 187 L. 600 de 2000, anteriormente \u00a0art. \u00a0197 \u00a0D. \u00a02700 \u00a0de \u00a01991) \u00a0y \u00a0no \u00a0admite \u00a0recurso alguno, adem\u00e1s de no ser \u00a0susceptibles \u00a0las \u00a0sentencias \u00a0de \u00a0reposici\u00f3n, \u00a0\u00fanica \u00a0impugnaci\u00f3n \u00a0que puede \u00a0intentarse \u00a0frente \u00a0a \u00a0pronunciamientos del m\u00e1ximo tribunal de la jurisdicci\u00f3n \u00a0ordinaria. \u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Corte Suprema de \u00a0Justicia, \u00a0Sala \u00a0de \u00a0Casaci\u00f3n \u00a0Penal, \u00a0administrando \u00a0justicia \u00a0en nombre de la \u00a0Rep\u00fablica y por autoridad de la ley, \u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>NO CASAR el fallo impugnado. \u00a0<\/p>\n<p>Contra \u00a0esta \u00a0sentencia \u00a0no \u00a0procede \u00a0recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0comun\u00edquese \u00a0y \u00a0devu\u00e9lvase \u00a0al \u00a0Tribunal de origen. C\u00famplase. \u00a0\u00a0<\/p>\n<p>\u00c1LVARO \u00a0ORLANDO P\u00c9REZ \u00a0PINZ\u00d3N \u00a0\u00a0<\/p>\n<p>FERNANDO \u00a0 \u00a0 \u00a0 E. \u00a0 \u00a0 \u00a0 ARBOLEDA \u00a0RIPOLL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 JORGE \u00a0E. C\u00d3RDOBA \u00a0POVEDA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>HERMAN \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 GAL\u00c1N \u00a0CASTELLANOS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0CARLOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0AUGUSTO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0G\u00c1LVEZ \u00a0ARGOTE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JORGE \u00a0 \u00a0 \u00a0 AN\u00cdBAL \u00a0 \u00a0 \u00a0 G\u00d3MEZ \u00a0GALLEGO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00c9DGAR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 LOMBANA \u00a0TRUJILLO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 CARLOS \u00a0EDUARDO \u00a0MEJ\u00cdA \u00a0ESCOBAR\u00a0\u00a0\u00a0\u00a0\u00a0 NILSON \u00a0 \u00a0PINILLA \u00a0 PINILLA \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 16167 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Magistrado ponente: \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Nilson Pinilla Pinilla \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Aprobado Acta N\u00b0 082 \u00a0\u00a0 Bogot\u00e1, \u00a0D. \u00a0C., julio dieciocho (18) de dos \u00a0mil dos (2002). \u00a0\u00a0 ASUNTO \u00a0 Se decide la casaci\u00f3n interpuesta en defensa \u00a0de \u00a0HERN\u00c1N \u00a0AUGUSTO [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5850","post","type-post","status-publish","format-standard","hentry","category-10"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/5850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=5850"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/5850\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=5850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=5850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=5850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}