{"id":56735,"date":"2023-12-22T15:42:57","date_gmt":"2023-12-22T15:42:57","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/12\/22\/stp7660-2021\/"},"modified":"2023-12-22T15:42:57","modified_gmt":"2023-12-22T15:42:57","slug":"stp7660-2021","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/12\/22\/stp7660-2021\/","title":{"rendered":"STP7660-2021"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>HUGO \u00a0QUINTERO BERNATE \u00a0<\/p>\n<p>Magistrado \u00a0Ponente \u00a0<\/p>\n<p>STP7660-2021 \u00a0<\/p>\n<p>Radicado \u00a0116016 \u00a0<\/p>\n<p>Acta \u00a0No.103 \u00a0<\/p>\n<p>Bogot\u00e1, D. \u00a0C., cuatro (4) de mayo de dos mil veintiuno (2021). \u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Resuelve \u00a0la Sala la impugnaci\u00f3n presentada por JAIRO EDUARDO MART\u00cdNEZ \u00a0SALAMANCA, en contra de la sentencia del 19 de marzo de 2021, emitida \u00a0por la Sala Penal del Tribunal Superior de Tunja (Boyac\u00e1), por \u00a0medio de la cual se tutel\u00f3 \u00a0su derecho fundamental al debido \u00a0proceso, \u00a0en el marco de la acci\u00f3n de tutela interpuesta por \u00e9l \u00a0en contra del Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y Medidas \u00a0de Seguridad de esa ciudad. \u00a0<\/p>\n<p>Adem\u00e1s \u00a0de la autoridad accionada, al tr\u00e1mite fue vinculado el Centro \u00a0de Servicios de los Juzgados de Ejecuci\u00f3n de Penas de Tunja, a \u00a0efectos de que se pronunciara sobre los hechos y pretensiones que son \u00a0se\u00f1alados en el escrito de tutela. \u00a0<\/p>\n<p>FUNDAMENTOS DE \u00a0LA ACCI\u00d3N \u00a0<\/p>\n<p>De acuerdo con el \u00a0escrito de tutela, JAIRO EDUARDO MART\u00cdNEZ SALAMANCA fue \u00a0condenado el 7 de marzo de 2016, por el Juzgado 5\u00ba Penal del \u00a0Circuito de Tunja, a la pena principal de 84 meses de prisi\u00f3n, \u00a0como autor responsable de los delitos de falsedad \u00a0en documento privado \u00a0y fraude \u00a0procesal; \u00a0en providencia en la cual se le reconoci\u00f3 el sustituto de la \u00a0prisi\u00f3n \u00a0domiciliaria. \u00a0Actualmente, su pena est\u00e1 siendo vigilado por el Juzgado 6\u00ba \u00a0de Ejecuci\u00f3n de Penas y Medidas de Seguridad de Tunja; \u00a0autoridad que, mediante auto del 16 de diciembre de 2019, le revoc\u00f3 \u00a0el beneficio de la prisi\u00f3n \u00a0domiciliaria \u00a0y le neg\u00f3 \u00a0el sustituto de la libertad \u00a0condicional. \u00a0Esta determinaci\u00f3n fue confirmada, \u00a0posteriormente, por el Juzgado de Conocimiento respectivo. \u00a0<\/p>\n<p>Por lo anterior, \u00a0JAIRO EDUARDO MART\u00cdNEZ SALAMANCA fue trasladado a la C\u00e1rcel \u00a0de Tunja, lugar en el cual estuvo durante el periodo comprendido \u00a0entre el 19 de octubre de 2020 y el 30 de noviembre de ese mismo a\u00f1o; \u00a0momento en el cual fue trasladado nuevamente a su residencia, en \u00a0cumplimiento del auto del 23 de noviembre, por medio del cual el \u00a0Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y Medidas de Seguridad \u00a0le concedi\u00f3 \u00a0la prisi\u00f3n \u00a0domiciliaria transitoria \u00a0al actor, con fundamento en lo normado en el Decreto-Ley 546 de 2020. \u00a0En dicha ocasi\u00f3n, el referido Despacho volvi\u00f3 a negarle \u00a0al actor el beneficio de la libertad \u00a0condicional, \u00a0con fundamento en el hecho de que ese estrado ya se hab\u00eda \u00a0pronunciado sobre ese punto en la providencia del 16 de diciembre de \u00a02019. \u00a0<\/p>\n<p>Indic\u00f3 el \u00a0actor que, el 15 de enero de 2021, le envi\u00f3 directamente al \u00a0Juzgado accionado un correo electr\u00f3nico en el que solicitaba \u00a0la redenci\u00f3n de su pena y, a la fecha de interposici\u00f3n \u00a0de la presente demanda de amparo, el estrado prenombrado no se hab\u00eda \u00a0pronunciado sobre su petici\u00f3n. Tambi\u00e9n refiri\u00f3 \u00a0que el 18 de enero siguiente, le envi\u00f3 a ese Despacho una \u00a0nueva solicitud de libertad \u00a0condicional \u00a0y que, a pesar del tiempo transcurrido, esa autoridad tampoco se \u00a0hab\u00eda pronunciado sobre ella. Dicha petici\u00f3n fue \u00a0reiterada en correo del 21 de enero. \u00a0<\/p>\n<p>Por considerar que \u00a0la anterior situaci\u00f3n denota una clara vulneraci\u00f3n de \u00a0sus derechos fundamentales de petici\u00f3n, \u00a0libertad \u00a0y al debido \u00a0proceso, \u00a0y al advertir que cumple con todos los presupuestos establecidos en \u00a0el art\u00edculo 64 del C\u00f3digo Penal para que le concedan la \u00a0libertad \u00a0provisional, \u00a0JAIRO EDUARDO MART\u00cdNEZ SALAMANCA demand\u00f3 que se le \u00a0ordene \u00a0al Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y Medidas de \u00a0Seguridad de Tunja que le d\u00e9 tr\u00e1mite a sus solicitudes \u00a0y que le conceda \u00a0la libertad \u00a0condicional \u00a0que reclama. \u00a0<\/p>\n<p>TR\u00c1MITE \u00a0DE LA PRIMERA INSTANCIA \u00a0<\/p>\n<p>1. \u00a0Por auto del 8 de marzo de 2021 se admiti\u00f3 \u00a0la presente acci\u00f3n de tutela y se corri\u00f3 \u00a0el respectivo traslado a las partes e intervinientes. \u00a0<\/p>\n<p>2. \u00a0El Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y Medidas de \u00a0Seguridad de Tunja indic\u00f3 que, en efecto, en ese estrado \u00a0judicial se vigila la condena de JAIRO EDUARDO MART\u00cdNEZ \u00a0SALAMANCA, qui\u00e9n fue condenado a la pena de 84 meses de \u00a0prisi\u00f3n por el Juzgado 5\u00ba Penal del Circuito de Tunja, \u00a0como autor responsable de los delitos de falsedad \u00a0en documento privado \u00a0y fraude \u00a0procesal. \u00a0De cara a los hechos y pretensiones esgrimidos en la demanda de \u00a0tutela, manifest\u00f3 lo siguiente: \u00a0<\/p>\n<p>(i) \u00a0Mediante auto interlocutorio del 16 de diciembre de 2019, ese \u00a0Despacho le revoc\u00f3 \u00a0al accionante el sustituto de la prisi\u00f3n \u00a0domiciliaria \u00a0y le neg\u00f3 \u00a0el beneficio de la libertad \u00a0condicional, \u00a0al no advertir cumplidos todos los requisitos establecidos en el \u00a0art\u00edculo 30 de la Ley 1709 de 2014. \u00a0<\/p>\n<p>(ii) \u00a0Mediante auto del 20 de mayo de 2020, el Despacho decidi\u00f3 no \u00a0reponer \u00a0la providencia del 16 de diciembre, aunque concedi\u00f3 el recurso \u00a0de apelaci\u00f3n ante el Juzgado de Conocimiento. \u00a0<\/p>\n<p>(iii) \u00a0Por auto del 30 de junio de 2020, el Juzgado 5\u00ba Penal del \u00a0Circuito de Tunja resolvi\u00f3 confirmar \u00a0el auto recurrido, al tiempo que orden\u00f3 la captura \u00a0del actor y le compuls\u00f3 copias ante la Fiscal\u00eda General \u00a0de la Naci\u00f3n por los delitos de fuga \u00a0de presos \u00a0y fraude \u00a0a resoluci\u00f3n judicial. \u00a0<\/p>\n<p>(iv) \u00a0Mediante auto del 7 de septiembre de 2020, el Juzgado Ejecutor orden\u00f3 \u00a0cumplir \u00a0lo decidido en providencia del 30 de junio de ese a\u00f1o, al \u00a0tiempo que declar\u00f3 improcedentes \u00a0los recursos presentados por el sentenciado en contra del auto del 20 \u00a0de mayo y neg\u00f3 \u00a0la declaratoria de nulidad \u00a0de lo actuado a partir de dicha fecha. \u00a0<\/p>\n<p>(v) \u00a0Mediante auto del 23 de noviembre de 2020, el prenombrado Despacho \u00a0determin\u00f3 no \u00a0reponer \u00a0el auto del 7 de septiembre, aunque concedi\u00f3 la apelaci\u00f3n \u00a0del mismo ante el Tribunal Superior de Tunja, en lo concerniente a la \u00a0nulidad. \u00a0Igualmente, volvi\u00f3 a negar \u00a0el beneficio de la libertad \u00a0condicional \u00a0y concedi\u00f3 \u00a0la prisi\u00f3n \u00a0domiciliaria transitoria, \u00a0de conformidad con lo dispuesto en el Decreto-Ley 546 de 2020. \u00a0<\/p>\n<p>A \u00a0continuaci\u00f3n, manifest\u00f3 que la Secretar\u00eda com\u00fan \u00a0a los Juzgados de Ejecuci\u00f3n de Penas y Medidas de Seguridad de \u00a0Tunja, remiti\u00f3 el proceso a la Sala Penal del Tribunal \u00a0Superior de esa ciudad, mediante oficio del 5 de marzo de 2021. Por \u00a0lo anterior, ese Despacho no cuenta actualmente con el expediente y, \u00a0por esa raz\u00f3n, solo cuando el mismo retorne del prenombrado \u00a0Tribunal, es que podr\u00e1 darles tr\u00e1mite a las nuevas \u00a0peticiones presentadas por JAIRO EDUARDO MART\u00cdNEZ SALAMANCA. \u00a0<\/p>\n<p>As\u00ed, \u00a0al no advertir que ese estrado hubiera desconocido los derechos \u00a0fundamentales del accionante, y al encontrar que esta acci\u00f3n \u00a0es manifiestamente improcedente, \u00a0demand\u00f3 que las pretensiones contenidas en el escrito de \u00a0tutela sean despachadas en sentido desfavorable \u00a0para el actor. \u00a0<\/p>\n<p>3. \u00a0Por su parte, el Centro de Servicios Administrativos de los Juzgados \u00a0de Ejecuci\u00f3n de Penas y Medidas de Seguridad de Tunja afirm\u00f3 \u00a0que recibi\u00f3 la solicitud de libertad \u00a0condicional \u00a0elevada por e sentenciado el 18 de enero de 2021. Sin embargo, al \u00a0encontrarse pendiente el tr\u00e1mite del recurso de apelaci\u00f3n \u00a0interpuesto contra el auto del 7 de septiembre de 2020, la causa no \u00a0fue ingresada al Despacho para su resoluci\u00f3n, pues se est\u00e1 \u00a0a la espera de las resultas del recurso de alzada. As\u00ed, al no \u00a0advertir desconocimiento alguno de las garant\u00edas fundamentales \u00a0del accionante, solicit\u00f3 ser desvinculado \u00a0de este tr\u00e1mite constitucional. \u00a0<\/p>\n<p>4. Visto lo \u00a0anterior, en sentencia del 19 de marzo de 2021, la Sala Penal del \u00a0Tribunal Superior de Tunja resolvi\u00f3 tutelar \u00a0el derecho fundamental al debido \u00a0proceso \u00a0de JAIRO EDUARDO MART\u00cdNEZ SALAMANCA y, en consecuencia, orden\u00f3 \u00a0lo siguiente: (i) a la Secretar\u00eda del Centro de Servicios \u00a0Administrativos de los Juzgados de Ejecuci\u00f3n de Penas y \u00a0Medidas de Seguridad de Tunja, que gestione y adelante los tr\u00e1mites \u00a0pertinente para ingresar, al Juzgado 6\u00ba de Ejecuci\u00f3n de \u00a0Penas y Medidas de Seguridad de esa ciudad, las peticiones que JAIRO \u00a0EDUDARDO MART\u00cdNEZ SALAMANCA radic\u00f3 en esa dependencia \u00a0el 18 y el 21 de enero de este a\u00f1o y (ii) al Juzgado \u00a0prenombrado, que, recibidos los correspondientes memoriales, proceda \u00a0a asignar el turno respectivo para resolver las solicitudes elevadas \u00a0por el accionante. \u00a0<\/p>\n<p>Como fundamento de \u00a0su decisi\u00f3n, sostuvo que las razones esgrimidas por el Juzgado \u00a0y el Centro de Servicios Administrativos no son suficientes para \u00a0justificar el hecho de que al actor no se le hayan resuelto sus \u00a0solicitudes, toda vez que la carpeta fue enviada a ese Tribunal con \u00a0posterioridad a que dichos memoriales fueren enviados y en tanto \u00a0ellos versan sobre un asunto distinto al que debe pronunciarse esa \u00a0Corporaci\u00f3n1. \u00a0Este \u00faltimo argumento, en particular, implica que la \u00a0competencia del Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y \u00a0Medidas de Seguridad no se encuentran suspendida de cara al \u00a0pronunciamiento que demanda el actor, de forma tal que a ese estrado \u00a0le corresponde emitir la correspondiente decisi\u00f3n dentro del \u00a0t\u00e9rmino que legalmente se encuentra establecido para ello. \u00a0<\/p>\n<p>Por \u00faltimo, \u00a0al advertir que JAIRO EDUARDO MART\u00cdNEZ SALAMANCA tiene la \u00a0costumbre de reiterar sus solicitudes tan pronto las manda, o de \u00a0interponer acciones de tutela sucesivas, con la finalidad de \u00a0presionar por un pronunciamiento \u00a0inmediato, la Sala Penal del \u00a0Tribunal Superior de Tunja inst\u00f3 \u00a0al accionante para que no abuse de su derecho de postulaci\u00f3n \u00a0y le permita al Juzgado accionado resolver sus solicitudes de acuerdo \u00a0con el turno que les corresponda, de manera que tambi\u00e9n se \u00a0puedan atender oportunamente las peticiones de los otros reos que se \u00a0encuentran a cargo de ese estrado. \u00a0<\/p>\n<p>5. Inconforme con \u00a0la decisi\u00f3n anterior, JAIRO EDUARDO MART\u00cdNEZ SALAMANCA \u00a0impugn\u00f3 \u00a0la sentencia del 19 de marzo de 2021, en extenso y confuso escrito, \u00a0en el que manifest\u00f3 lo siguiente: (i) que no era necesario \u00a0ordenarle al Centro de Servicios Administrativos que le remita sus \u00a0solicitudes al Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y Medidas \u00a0de Seguridad, toda vez que \u00e9l tambi\u00e9n hab\u00eda \u00a0radicado esas solicitudes ante dicha autoridad de manera directa; \u00a0(ii) que el a \u00a0quo \u00a0no pod\u00eda ordenarle al prenombrado Juzgado que resolviera sus \u00a0solicitudes cuando llegara el respectivo turno, sino dentro del \u00a0t\u00e9rmino legal que establece el art\u00edculo 472 de la Ley \u00a0906 de 2004; (iii) que, de todas formas, sus peticiones est\u00e1n \u00a0sujetas al t\u00e9rmino general prescrito para responder \u00a0solicitudes, es decir, 15 d\u00edas h\u00e1biles, y el \u00a0incumplimiento de dicho t\u00e9rmino es vulneratorio de su derecho \u00a0fundamental de petici\u00f3n; \u00a0(iv) que \u00e9l no tiene la intenci\u00f3n de abusar de su \u00a0derecho de postulaci\u00f3n, \u00a0pues lo que \u00e9l ha hecho se reduce, simplemente, a exigir el \u00a0respeto y la garant\u00eda de sus derechos fundamentales, \u00a0vulnerados por el Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y \u00a0Medidas de Seguridad de Tunja y (v) que no entiende c\u00f3mo no se \u00a0le tutel\u00f3 su derecho fundamental a la libertad, \u00a0toda vez que la demora en la resoluci\u00f3n de su petici\u00f3n \u00a0de libertad \u00a0condicional \u00a0implica, precisamente, la afectaci\u00f3n a esa garant\u00eda \u00a0constitucional. \u00a0<\/p>\n<p>Con fundamento en \u00a0todo lo anterior, JAIRO EDUARDO MART\u00cdNEZ SALAMANCA demand\u00f3 \u00a0que la sentencia del 16 de marzo sea modificada \u00a0en el sentido de agregar la tutela por los derechos fundamentales de \u00a0petici\u00f3n \u00a0y a la libertad, \u00a0y de ordenarle \u00a0al Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y Medidas de \u00a0Seguridad que, en el t\u00e9rmino de 48 horas contadas a partir de \u00a0la notificaci\u00f3n de esta sentencia, proceda a resolver sus \u00a0solicitudes de libertad \u00a0condicional \u00a0y de redenci\u00f3n \u00a0de pena. \u00a0<\/p>\n<p>6. La impugnaci\u00f3n \u00a0le fue concedida mediante auto del 5 de abril de 2021. \u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE LA CORTE \u00a0<\/p>\n<p>1. \u00a0Conforme con el art\u00edculo 32 del Decreto 2591 de 1991, la Sala \u00a0es competente para desatar la alzada, por cuanto la decisi\u00f3n \u00a0sobre la que recae fue proferida por un Tribunal Superior de Distrito \u00a0Judicial. \u00a0<\/p>\n<p>2. El art\u00edculo \u00a086 de la Constituci\u00f3n Pol\u00edtica establece que toda \u00a0persona tiene derecho a promover acci\u00f3n de tutela ante los \u00a0jueces con miras a obtener la protecci\u00f3n inmediata de sus \u00a0derechos fundamentales cuando, por acci\u00f3n u omisi\u00f3n, le \u00a0sean vulnerados o amenazados por cualquier autoridad p\u00fablica o \u00a0por particulares, en los casos previstos de forma expresa en la ley, \u00a0siempre que no exista otro medio de defensa judicial o, si existe, \u00a0cuando se utiliza como mecanismo transitorio para evitar un perjuicio \u00a0irremediable. \u00a0<\/p>\n<p>3. Vistos los \u00a0antecedentes que obran al interior de este expediente, considera la \u00a0Sala que debe entrar a determinar si es procedente entrar a modificar \u00a0la sentencia de primera instancia en el sentido que reclama el \u00a0impugnante, o si, por el contrario, dicha providencia se encuentra \u00a0ajustada a derecho. \u00a0<\/p>\n<p>4. Ahora bien, \u00a0descendiendo de una vez al caso concreto, observa la Sala que la \u00a0sentencia del 16 de marzo de 2021, emitida por la Sala Penal del \u00a0Tribunal Superior de Tunja, debe ser confirmada, \u00a0en su integridad, con fundamento en las siguientes razones: \u00a0<\/p>\n<p>i. Frente a la \u00a0tutela del derecho fundamental de petici\u00f3n, \u00a0es necesario precisar que los memoriales que JAIRO EDUARDO MART\u00cdNEZ \u00a0SALAMANCA ha remitido al Juzgado 6\u00ba de Ejecuci\u00f3n de Penas \u00a0y Medidas de Seguridad de Tunja no se encuentran amparados por dicha \u00a0garant\u00eda, sino por el derecho fundamental al debido \u00a0proceso, \u00a0en su faceta del derecho de postulaci\u00f3n. \u00a0Ello, por cuanto son memoriales presentados en el marco de un \u00a0procedimiento de car\u00e1cter jurisdiccional, y el derecho de \u00a0petici\u00f3n \u00a0solo se predica de cara a actuaciones administrativas. En esta \u00a0medida, a sus solicitudes no les es aplicable el t\u00e9rmino \u00a0previsto en la Ley 1755 de 2015, que modifica la Ley 1437 de 2011 y, \u00a0por consiguiente, la falta en su respuesta no implica el \u00a0desconocimiento del derecho de petici\u00f3n, \u00a0sino de la garant\u00eda constitucional del debido \u00a0proceso. \u00a0<\/p>\n<p>ii. Frente al \u00a0derecho fundamental a la libertad, \u00a0baste decir que dicha garant\u00eda no se protege mediante la \u00a0acci\u00f3n de tutela sino mediante el mecanismo constitucional del \u00a0h\u00e1beas \u00a0corpus. \u00a0En cualquier caso, la situaci\u00f3n actual de privaci\u00f3n de \u00a0la libertad de JAIRO EDUARDO MART\u00cdNEZ SALAMANCA no se advierte \u00a0arbitraria o injustificada, toda vez que sobre \u00e9l pesa una \u00a0condena de naturaleza penal. Del mismo modo, es importante recordarle \u00a0que la libertad \u00a0condicional \u00a0que \u00e9l solicita no corresponde a un derecho, \u00a0en estricto sentido, sino a un beneficio \u00a0o gracia \u00a0que le concede el Juez de Ejecuci\u00f3n de Penas, si se advierten \u00a0cumplidos una serie de requisitos objetivos y subjetivos. Evidencia \u00a0de lo anterior es el hecho de que, incluso si el accionante llegare a \u00a0cumplir la totalidad de los requisitos establecidos legalmente, el \u00a0Juez de Ejecuci\u00f3n de Penas podr\u00eda negar \u00a0la libertad \u00a0condicional \u00a0con fundamento en la valoraci\u00f3n de la gravedad de la conducta \u00a0punible. Esto implica que, hasta tanto MART\u00cdNEZ SALAMANCA no \u00a0cumpla la totalidad de su condena, no se concretar\u00e1 sobre \u00e9l \u00a0un verdadero \u201cderecho\u201d \u00a0a la libertad, \u00a0con la vocaci\u00f3n de ser exigido judicialmente. \u00a0<\/p>\n<p>iii. La orden dada \u00a0al Centro de Servicios Administrativos se advierte correcta, toda vez \u00a0que, por mucho que JAIRO EDUARDO MART\u00cdNEZ SALAMANCA haya \u00a0remitido sus solicitudes de manera dicta al Juzgado 6\u00ba de \u00a0Ejecuci\u00f3n de Penas y Medidas de Seguridad, lo cierto es que \u00a0las mismas no pueden ingresar al Despacho de cualquier manera, sino \u00a0por los canales administrativos habilitados para el efecto. Por lo \u00a0anterior, es correcto que se le ordene a dicha dependencia que los \u00a0remita al Despacho accionado de acuerdo con el procedimiento interno \u00a0que se encuentre establecido, de forma que tales memoriales puedan \u00a0ingresar de manera formal al expediente. Por ello, no se advierte \u00a0irregularidad alguna con respecto a la emisi\u00f3n de la segunda \u00a0disposici\u00f3n contenida en la sentencia de tutela impugnada. \u00a0<\/p>\n<p>iv. Tampoco se \u00a0advierte arbitrariedad alguna en lo que respecta a la orden de \u00a0resolver las solicitudes de acuerdo con el turno que les sea \u00a0asignado, pues, como bien debe conocer el actor, \u00e9l no es la \u00a0\u00fanica persona cuya condena est\u00e1 siendo vigilada por el \u00a0Juzgado 6\u00ba de Ejecuci\u00f3n de Penas y Medidas de Seguridad \u00a0de Tunja. La emisi\u00f3n de una orden como la pretende el \u00a0accionante podr\u00eda implicar que el Despacho demandado tenga que \u00a0darles prelaci\u00f3n a las solicitudes de JAIRO EDUARDO MART\u00cdNEZ \u00a0SALAMANCA sobre las de otros condenados que, posiblemente, podr\u00edan \u00a0haber sido elevadas antes que aquellas sobre las que el actor reclama \u00a0la intervenci\u00f3n del juez constitucional; situaci\u00f3n que \u00a0degenerar\u00eda en la vulneraci\u00f3n del derecho fundamental a \u00a0la igualdad \u00a0de los otros condenados. Por lo anterior, tampoco se acceder\u00e1 \u00a0a las pretensiones del accionante con fundamento en este espec\u00edfico \u00a0argumento. \u00a0<\/p>\n<p>v. Sobre el \u00a0incumplimiento del plazo previsto en el art\u00edculo 472 de la Ley \u00a0906 de 2004, vale la pena indicar que el desconocimiento mismo solo \u00a0puede ser constitutivo de una vulneraci\u00f3n al derecho \u00a0fundamental al debido \u00a0proceso \u00a0cuando la mora se encuentre injustificada \u00a0y sea consecuencia de un actuar negligente \u00a0por parte del Despacho judicial. Una de las posibles justificaciones \u00a0que se podr\u00edan esgrimir para su exceso es, precisamente, la \u00a0existencia de otras peticiones previas a las que haya que darles \u00a0prelaci\u00f3n, como ya fue explicado previamente. En esa medida, \u00a0tampoco es posible acceder a las pretensiones del accionante por v\u00eda \u00a0de esta l\u00ednea argumentativa. \u00a0<\/p>\n<p>vi. Por \u00faltimo, \u00a0tampoco se advierte la necesidad de modificar la orden de instar \u00a0al accionante a no abusar \u00a0de su derecho de postulaci\u00f3n \u00a0pues, en efecto, del expediente se desprende que esta persona tiene \u00a0la costumbre de elevar memoriales de manera reiterada, para solicitar \u00a0beneficios que le hab\u00edan sido negados previamente, y de \u00a0interponer acciones de tutela ante la m\u00e1s m\u00ednima \u00a0eventualidad. De hecho, la presente situaci\u00f3n tiene su origen \u00a0en el hecho del que el accionante suele elevar solicitudes e \u00a0interponer recursos m\u00e1s r\u00e1pido de lo que puede \u00a0despacharlos el Juzgado accionado o sus superiores jer\u00e1rquicos, \u00a0lo que genera una situaci\u00f3n de congesti\u00f3n que dificulta \u00a0a\u00fan m\u00e1s el tr\u00e1mite de sus peticiones. Por lo \u00a0anterior, tampoco se acceder\u00e1 a las pretensiones del actor en \u00a0lo que respecta a este punto espec\u00edfico. \u00a0<\/p>\n<p>Visto todo lo \u00a0anterior, advierte la Sala que las determinaciones contenidas en la \u00a0parte resolutiva de la sentencia impugnada son razonables \u00a0y se encuentran debida y suficientemente argumentadas, lo que implica \u00a0que fueron adoptadas conforme a derecho. No encuentra, por lo tanto, \u00a0argumento alguno que le permita a esta Corte modificarlas y, en esa \u00a0medida, se proceder\u00e1 a confirmar \u00a0la providencia recurrida. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la SALA DE DECISI\u00d3N DE TUTELAS \u00a0No. 2 DE LA SALA DE CASACI\u00d3N PENAL DE LA CORTE SUPREMA DE \u00a0JUSTICIA, administrando \u00a0justicia en nombre de la Rep\u00fablica y por autoridad de la Ley, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>1. CONFIRMAR la \u00a0sentencia del 19 de marzo de 2021, emitida por la Sala Penal del \u00a0Tribunal Superior de Tunja (Boyac\u00e1), por medio de la cual se \u00a0tutel\u00f3 \u00a0el derecho fundamental al debido \u00a0proceso \u00a0de JAIRO EDUARDO MART\u00cdNEZ SALAMANCA, en el marco de la acci\u00f3n \u00a0de tutela interpuesta por \u00e9l en contra del Juzgado 6\u00ba de \u00a0Ejecuci\u00f3n de Penas y Medidas de Seguridad de esa ciudad. \u00a0<\/p>\n<p>2. NOTIFICAR \u00a0esta \u00a0providencia de conformidad con el art\u00edculo 30 del Decreto 2591 \u00a0de 1991. \u00a0<\/p>\n<p>3. REMITIR el \u00a0expediente a la Corte Constitucional para su eventual revisi\u00f3n. \u00a0<\/p>\n<p>NOTIF\u00cdQUESE \u00a0Y C\u00daMPLASE. \u00a0<\/p>\n<p>HUGO \u00a0QUINTERO BERNATE \u00a0<\/p>\n<p>LUIS \u00a0ANTONIO HERN\u00c1NDEZ BARBOSA \u00a0<\/p>\n<p>FABIO \u00a0OSPITIA GAR\u00d3N \u00a0<\/p>\n<p>NUBIA YOLANDA \u00a0NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0En efecto, las solicitudes del actor se reducen a una nueva petici\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de libertad \u00a0 \u00a0 \u00a0 \u00a0 \u00a0condicional y a la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0realizaci\u00f3n de un nuevo estudio de redenci\u00f3n de pena, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0al tiempo que el recurso de alzada sobre el que debe pronunciarse el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Tribunal se refiere a una solicitud de nulidad, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de cara a lo actuado a partir del auto del 20 de mayo de 2020. \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 HUGO \u00a0QUINTERO BERNATE \u00a0 Magistrado \u00a0Ponente \u00a0 STP7660-2021 \u00a0 Radicado \u00a0116016 \u00a0 Acta \u00a0No.103 \u00a0 Bogot\u00e1, D. \u00a0C., cuatro (4) de mayo de dos mil veintiuno (2021). \u00a0 VISTOS \u00a0 Resuelve \u00a0la Sala la impugnaci\u00f3n presentada por JAIRO EDUARDO MART\u00cdNEZ \u00a0SALAMANCA, en contra de la sentencia del 19 de marzo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,36],"tags":[],"class_list":["post-56735","post","type-post","status-publish","format-standard","hentry","category-30","category-mayo"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/56735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=56735"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/56735\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=56735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=56735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=56735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}