{"id":5658,"date":"2023-09-08T16:23:39","date_gmt":"2023-09-08T16:23:39","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1490313-06-02\/"},"modified":"2023-09-08T16:23:39","modified_gmt":"2023-09-08T16:23:39","slug":"1490313-06-02","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1490313-06-02\/","title":{"rendered":"14903(13-06-02)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 14903 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACION PENAL \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>Dr. Carlos E. Mej\u00eda Escobar \u00a0<\/p>\n<p>Aprobado\u00a0 Acta No. 62 \u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D.C.,\u00a0 \u00a0trece\u00a0 \u00a0(13)\u00a0 \u00a0de\u00a0 \u00a0 junio\u00a0\u00a0 \u00a0de\u00a0 \u00a0dos\u00a0 \u00a0mil\u00a0 \u00a0dos\u00a0 \u00a0(2002). \u00a0\u00a0<\/p>\n<p>V\u00a0 \u00a0I\u00a0 \u00a0S\u00a0 \u00a0T\u00a0 \u00a0O\u00a0 \u00a0S\u00a0 \u00a0\u00a0<\/p>\n<p>Resuelve la Sala lo que en derecho corresponda \u00a0respecto \u00a0de \u00a0los \u00a0requisitos formales de la demanda de casaci\u00f3n presentada por \u00a0el defensor del procesado LUIS HONORIO MEJIA MARULANDA. \u00a0\u00a0<\/p>\n<p>H \u00a0E \u00a0C \u00a0H O S\u00a0 \u00a0\u00a0<\/p>\n<p>La \u00a0Sala \u00a0Penal \u00a0del \u00a0Tribunal \u00a0Superior \u00a0del \u00a0Distrito Judicial de Medell\u00edn (Antioquia), los reconstruy\u00f3 as\u00ed: \u00a0\u00a0<\/p>\n<p>\u201cHasta un mes y medio antes a la ocurrencia \u00a0de \u00a0 los \u00a0hechos \u00a0materia \u00a0de \u00a0juzgamiento, \u00a0veintitr\u00e9s \u00a0de \u00a0noviembre \u00a0de \u00a0mil \u00a0novecientos \u00a0noventa y cinco (23-XI-95), LUIS HONORIO MEJIA MARULANDA y la joven \u00a0Luz \u00a0Mery \u00a0Ospina \u00a0Suaza \u00a0ven\u00edan sosteniendo un informal concubinato en el cual \u00a0fue \u00a0procreada \u00a0una \u00a0ni\u00f1a.\u00a0 Para la fecha en menci\u00f3n ya las relaciones, a \u00a0decir de ambos, se hab\u00edan terminado. \u00a0\u00a0<\/p>\n<p>\u201cEse \u00a0d\u00eda, a eso de las nueve de la noche, \u00a0Fabi\u00e1n \u00a0de \u00a0Jes\u00fas \u00a0Salavarrieta Cadavid, joven trabajador de la firma Postobon \u00a0que \u00a0por \u00a0su \u00a0oficio \u00a0&#8211; \u00a0repartidor \u00a0&#8211;\u00a0 \u00a0trab\u00f3 amistad con Luz Mery Ospina \u00a0Suaza, \u00a0estaba \u00a0de visita, previa llamada telef\u00f3nica, en el domicilio de \u00e9sta, \u00a0sito \u00a0en \u00a0la \u00a0calle \u00a045AB \u00a0No. \u00a011C \u00a0&#8211; \u00a02, \u00a0barrio \u00a0Caunces \u00a0de \u00a0Oriente de esta \u00a0ciudad.\u00a0 \u00a0Se hallaba conversando en la sala cuando hizo su aparici\u00f3n MEJIA \u00a0MARULANDA, \u00a0el ex &#8211; amante de la dama, con otros dos sujetos apodados \u201cNene\u201d \u00a0y \u00a0\u201cGallo\u201d.\u00a0 \u00a0Ante \u00a0tal \u00a0actitud aqu\u00e9llos se dirigieron inicialmente a \u00a0las \u00a0escalas \u00a0que \u00a0conduc\u00edan \u00a0al \u00a0segundo \u00a0piso \u00a0del inmueble, pero hasta all\u00ed \u00a0fueron \u00a0seguidos \u00a0por \u00a0los \u00a0inoportunos \u00a0visitantes.\u00a0 \u00a0Estaban en ese sitio \u00a0cuando \u00a0de \u00a0improviso, \u00a0y \u00a0por \u00a0orden \u00a0de \u00a0LUIS \u00a0HONORIO, \u00a0el \u00a0individuo apodado \u00a0\u201cNene\u201d \u00a0accion\u00f3, \u00a0a \u00a0corta distancia, varias veces, un arma de fuego contra \u00a0el \u00a0inerme \u00a0Salavarrieta \u00a0Cadavid.\u00a0 \u00a0Todo \u00a0indica \u00a0que \u00a0de \u00a0inmediato MEJIA \u00a0MARULANDA \u00a0tom\u00f3 \u00a0el \u00a0arma \u00a0que \u00a0portaba \u201cGallo\u201d y con ella \u201cRemat\u00f3\u201d al \u00a0infortunado \u00a0visitante.\u00a0 \u00a0\u201cLUIS \u00a0HONORIO, \u00a0dice \u00a0la \u00a0testigo \u00a0principal y \u00a0\u00fanica, \u00a0recogi\u00f3 el arma del que no le s\u00e9 el nombre y luego sent\u00ed que sonaron \u00a0m\u00e1s \u00a0disparos\u201d.\u00a0 \u00a0Seis \u00a0impactos \u00a0en \u00a0total, \u00a0la \u00a0mayor\u00eda en la cabeza, \u00a0recibi\u00f3 la v\u00edctima. \u00a0\u00a0<\/p>\n<p>\u201cNo \u00a0contentos \u00a0con \u00a0lo anterior, y ante la \u00a0huida \u00a0apresurada \u00a0de la mujer, los agresores se dieron a destruir los bienes de \u00a0la \u00a0vivienda, \u00a0causando \u00a0graves \u00a0da\u00f1os.\u00a0 Luego se dirigieron al exterior e \u00a0incineraron \u00a0la motocicleta, marca Yamaha, DT 175, color gris, de placas CJE 09, \u00a0de propiedad de Salavarrieta Cadavid\u201d. \u00a0\u00a0<\/p>\n<p>A \u00a0N \u00a0T \u00a0E \u00a0C \u00a0E \u00a0D \u00a0E \u00a0N \u00a0T \u00a0E S \u00a0\u00a0<\/p>\n<p>1.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a023 de noviembre de 1995 la Fiscal\u00eda \u00a0171 \u00a0Delegada \u00a0de \u00a0la \u00a0Unidad \u00a0de \u00a0Reacci\u00f3n \u00a0Inmediata \u00a0de \u00a0Medell\u00edn \u00a0realiz\u00f3 \u00a0diligencia \u00a0de levantamiento de cad\u00e1ver en la direcci\u00f3n anotada en los hechos, \u00a0del \u00a0occiso \u00a0Fabi\u00e1n \u00a0de \u00a0Jes\u00fas Salavarrieta Cadavid. En la misma diligencia se \u00a0recibi\u00f3 \u00a0testimonio \u00a0a \u00a0Luz \u00a0Mery \u00a0Ospina \u00a0Suaza, quien se\u00f1al\u00f3 a LUIS HONORIO \u00a0MEJIA \u00a0MARULANDA \u00a0y \u00a0a \u00a0alias \u00a0Nene \u00a0como \u00a0los responsables del homicidio,\u00a0 \u00a0Inmediatamente \u00a0se \u00a0practicaron diligencias de allanamiento en los domicilios de \u00a0los \u00a0imputados, \u00a0que \u00a0quedan \u00a0en \u00a0vecindad \u00a0del \u00a0lugar \u00a0de \u00a0los hechos, pero con \u00a0resultados negativos. \u00a0\u00a0<\/p>\n<p>2.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a02 \u00a0de \u00a0febrero \u00a0de \u00a01996 \u00a0se orden\u00f3 \u00a0apertura \u00a0de \u00a0instrucci\u00f3n \u00a0y \u00a0la vinculaci\u00f3n de LUIS HONORIO MEJIA MARULANDA y \u00a0Jhon \u00a0Arley \u00a0Acevedo \u00a0Gallego. \u00a0De \u00a0aquel \u00a0se recibi\u00f3 indagatoria y se defini\u00f3 \u00a0situaci\u00f3n \u00a0jur\u00eddica el 21 de febrero de 1996 mediante imposici\u00f3n de medida de \u00a0aseguramiento \u00a0de \u00a0detenci\u00f3n \u00a0preventiva.\u00a0 \u00a0El \u00a013 de junio de 1997 (folio \u00a0176) \u00a0se \u00a0calific\u00f3 el m\u00e9rito del sumario con resoluci\u00f3n de acusaci\u00f3n, la que \u00a0apelada \u00a0por \u00a0el defensor del acusado fue confirmada por una Fiscal de la Unidad \u00a0Delegada \u00a0 ante \u00a0los \u00a0Tribunales \u00a0Superiores \u00a0de \u00a0los \u00a0Distritos \u00a0Judiciales \u00a0de \u00a0Medell\u00edn \u00a0y \u00a0Antioquia \u00a0mediante \u00a0la \u00a0suya \u00a0del \u00a01 \u00a0de \u00a0agosto \u00a0de \u00a01997 (folio \u00a0200). \u00a0\u00a0<\/p>\n<p>3.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a0Juzgado \u00a03\u00b0 \u00a0Penal \u00a0del Circuito de \u00a0Medell\u00edn \u00a0tramit\u00f3 \u00a0la \u00a0fase de juzgamiento que culmin\u00f3 con la sentencia del 5 \u00a0de \u00a0febrero de 1998 por medio de la cual conden\u00f3 a LUIS HONORIO MEJIA MARULANDA \u00a0a \u00a0la \u00a0pena \u00a0principal \u00a0de \u00a043 \u00a0a\u00f1os \u00a0de prisi\u00f3n como autor responsable de los \u00a0delitos \u00a0de \u00a0homicidio \u00a0agravado, \u00a0da\u00f1o en bien ajeno y porte ilegal de arma de \u00a0fuego de defensa personal. \u00a0\u00a0<\/p>\n<p>4.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0Por \u00a0apelaci\u00f3n \u00a0que \u00a0interpusiera \u00a0el \u00a0defensor \u00a0del \u00a0procesado \u00a0la \u00a0Sala \u00a0Penal \u00a0del \u00a0Tribunal \u00a0Superior \u00a0del Distrito \u00a0Judicial \u00a0de \u00a0Medell\u00edn conoci\u00f3 del fallo de primera instancia para confirmarlo \u00a0mediante el suyo del 6 de mayo de 1998. \u00a0\u00a0<\/p>\n<p>5.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Contra el fallo del Tribunal se interpuso \u00a0recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n por parte del defensor del procesado, que \u00a0se sustent\u00f3 con la demanda que a continuaci\u00f3n se sintetiza. \u00a0\u00a0<\/p>\n<p>L \u00a0A\u00a0\u00a0\u00a0 \u00a0D \u00a0E \u00a0M \u00a0A \u00a0N \u00a0D \u00a0A \u00a0\u00a0<\/p>\n<p>Se \u00a0presenta \u00a0con fundamento en el inciso 2\u00b0 \u00a0del \u00a0art\u00edculo 220 del C\u00f3digo de Procedimiento Penal.\u00a0 Enuncia la causal y \u00a0formula \u00a0el \u00a0cargo como \u201cviolaci\u00f3n indirecta de la ley sustancial en error de \u00a0hecho por falso juicio de identidad\u201d. \u00a0\u00a0<\/p>\n<p>Afirma \u00a0que \u00a0las \u00a0normas \u00a0violadas \u00a0son \u00a0los \u00a0art\u00edculos \u00a0254 y 294 del C\u00f3digo de Procedimiento Penal que se\u00f1alaban la forma \u00a0como \u00a0deb\u00edan \u00a0ser \u00a0apreciadas \u00a0las \u00a0pruebas \u00a0y \u00a0defin\u00eda \u00a0los criterios para la \u00a0apreciaci\u00f3n del testimonio, respectivamente. \u00a0\u00a0<\/p>\n<p>El desarrollo del cargo lo hace con fundamento \u00a0en \u00a0citas de tratadistas extranjeros. Desde esas opiniones analiza el testimonio \u00a0de \u00a0la \u00a0se\u00f1ora \u00a0Luz \u00a0Mery \u00a0Ospina \u00a0Suaza, \u00a0para concluir que \u201cse sobrevalor\u00f3 \u00a0tangencialmente \u00a0lo \u00a0vertido \u00a0en \u00a0la primera jurada desestimando lo dicho por la \u00a0misma \u00a0testigo \u00a0en eventos posteriores cuando no le asist\u00edan las circunstancias \u00a0eminentemente \u00a0psicol\u00f3gicas \u00a0como \u00a0el \u00a0temor, \u00a0el \u00a0odio, \u00a0la venganza y el amor \u00a0cuales \u00a0eran \u00a0las determinantes subjetivas que alienaron la declaraci\u00f3n inicial \u00a0que \u00a0fundamenta \u00a0el \u00a0ad \u00a0quem \u00a0como \u00a0determinante \u00a0en \u00a0la reconstrucci\u00f3n de los \u00a0hechos, \u00a0es \u00a0pues \u00a0esta testiga \u00fanica suceptible (sic) de una tacha probatoria, \u00a0para \u00a0lo \u00a0cual \u00a0el \u00a0fallador \u00a0desconociendo \u00a0precisas normas sobre la materia no \u00a0apreci\u00f3 \u00a0 en \u00a0 su \u00a0 conjunto, \u00a0 conforme \u00a0 a \u00a0 los \u00a0 criterios \u00a0 de \u00a0 la \u00a0 sana \u00a0cr\u00edtica\u201d. \u00a0\u00a0<\/p>\n<p>Cita \u00a0varios apartes de la declaraci\u00f3n de la \u00a0testigo \u00a0y \u00a0de sus posteriores ampliaciones, para destacar contradicciones de su \u00a0relato \u00a0respecto \u00a0de \u00a0hechos \u00a0como \u00a0la \u00a0forma \u00a0de \u00a0ingreso de LUIS HONORIO MEJIA \u00a0MARULANDA \u00a0a \u00a0la vivienda de su ex compa\u00f1era Luz Mery Ospina Suaza; la forma en \u00a0que \u00a0se encontraron los agresores con la v\u00edctima en esa misma residencia; sobre \u00a0la \u00a0forma como se inici\u00f3 la agresi\u00f3n; sobre cu\u00e1l fue la actitud del procesado \u00a0LUIS \u00a0HONORIO; \u00a0y sobre \u201ccu\u00e1l fue el espacio temporal que transcurri\u00f3 con la \u00a0presencia \u00a0 \u00a0de \u00a0 \u00a0los \u00a0 \u00a0tres \u00a0 \u00a0sujetos \u00a0 que \u00a0 ingresaron \u00a0 a \u00a0 la \u00a0 vivienda \u00a0(&#8230;)\u201d. \u00a0\u00a0<\/p>\n<p>El \u00a0censor \u00a0encuentra \u00a0contradicciones \u00a0que \u00a0califica \u00a0de \u00a0\u201cevidentes\u201d \u00a0y \u00a0concluye, \u00a0con \u00a0fundamento \u00a0en un aparte de la \u00a0ampliaci\u00f3n \u00a0de \u00a0la \u00a0declaraci\u00f3n \u00a0de \u00a0la testigo Luz Mery Ospina Suaza que ella \u00a0estaba \u00a0alienada por circunstancias de inter\u00e9s, pasi\u00f3n, dolor, odio o amor que \u00a0\u201cconstituyen \u00a0en \u00a0s\u00edntesis \u00a0la \u00a0tergiversaci\u00f3n \u00a0retrospectiva de lo visto, o \u00a0escuchado \u00a0en \u00a0veces \u00a0en \u00a0desfavor \u00a0de \u00a0la \u00a0persona \u00a0que \u00a0en \u00a0su \u00a0momento quiere \u00a0comprometer\u201d. \u00a0\u00a0<\/p>\n<p>De acuerdo a ello, al demandante le parece que \u00a0fundamentar \u00a0la \u00a0sentencia \u00a0en el testimonio de Luz Mery Ospina Suaza, sin tener \u00a0en \u00a0cuenta \u00a0la \u00a0capacidad ps\u00edquica que le asist\u00eda a la testigo, es contrario a \u00a0los \u00a0presupuestos \u00a0normativos, \u00a0pues \u00a0se \u00a0trata \u00a0de \u00a0un testimonio que carece de \u00a0credibilidad.\u00a0 \u00a0 \u00a0Esa \u00a0 \u00a0testigo, \u00a0 dice \u00a0 el \u00a0 defensor,\u00a0 \u00a0 por \u00a0 sus \u00a0condiciones\u00a0 \u00a0mentales \u00a0de \u00a0ofuscaci\u00f3n debe considerarse como una alienada \u00a0cuyo \u00a0dicho \u00a0no \u00a0puede \u00a0tenerse \u00a0en \u00a0cuenta.\u00a0 \u00a0Por \u00a0ello \u00a0solicita \u00a0que \u00a0se \u00a0\u201cdeclare \u00a0que \u00a0la \u00a0sentencia \u00a0es \u00a0violatoria \u00a0por \u00a0v\u00eda \u00a0indirecta \u00a0de \u00a0la ley \u00a0sustancial \u00a0en \u00a0error \u00a0de hecho por falso juicio de identidad y por consiguiente \u00a0se modifique la condena\u201d. \u00a0\u00a0<\/p>\n<p>C O N S I D E R A C I O N E S \u00a0<\/p>\n<p>1.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0demanda \u00a0debe \u00a0ser \u00a0rechazada por no \u00a0reunir \u00a0los requisitos del art\u00edculo 212 del C\u00f3digo de Procedimiento Penal (225 \u00a0del \u00a0C\u00f3digo \u00a0derogado), \u00a0espec\u00edficamente el ordinal 3\u00b0 de tal norma\u00a0 que \u00a0le \u00a0impone a quien recurre en casaci\u00f3n la obligaci\u00f3n de indicar en forma clara \u00a0y \u00a0 precisa \u00a0 los \u00a0 fundamentos \u00a0 del \u00a0 ataque \u00a0 y \u00a0 las \u00a0 normas \u00a0 que \u00a0 estime \u00a0infringidas. \u00a0\u00a0<\/p>\n<p>2.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El\u00a0 censor eligi\u00f3 la causal primera \u00a0cuerpo \u00a0segundo \u00a0para \u00a0dentro \u00a0de \u00a0ella \u00a0se\u00f1alar \u00a0que \u00a0se \u00a0habr\u00eda incurrido en \u00a0violaci\u00f3n \u00a0 indirecta \u00a0de \u00a0los\u00a0 \u00a0art\u00edculos \u00a0254 \u00a0y \u00a0294 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0derogado \u00a0(238 y 277 respectivamente, del vigente), aunque \u00a0sin \u00a0se\u00f1alar \u00a0exactamente \u00a0el concepto de la violaci\u00f3n, ni por qu\u00e9 estima que \u00a0tales \u00a0disposiciones \u00a0son normas sustanciales.\u00a0 Esto \u00faltimo, por cuanto la \u00a0Corte \u00a0ya \u00a0ha \u00a0se\u00f1alado \u00a0en \u00a0otras \u00a0ocasiones \u00a0que \u00a0ese \u00a0tipo \u00a0de normas no son \u00a0sustanciales, \u00a0sino \u00a0mandatos \u00a0instrumentales que desarrollan el postulado de la \u00a0sana \u00a0cr\u00edtica\u00a0 \u00a0y, por tanto, de ninguna manera disposiciones de car\u00e1cter \u00a0material o sustancial. \u00a0\u00a0<\/p>\n<p>3.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Elegida la causal primera cuerpo segundo \u00a0&#8211; \u00a0violaci\u00f3n \u00a0indirecta \u00a0&#8211; el censor formul\u00f3 dentro de ella un \u00fanico cargo de \u00a0error \u00a0de \u00a0hecho \u00a0por falso juicio de identidad.\u00a0 El yerro habr\u00eda ocurrido \u00a0respecto \u00a0del \u00a0testimonio de la se\u00f1ora Luz Mery Ospina Suaza.\u00a0 Sin embargo \u00a0y \u00a0a \u00a0pesar de la claridad en la enunciaci\u00f3n de la causal y la formulaci\u00f3n del \u00a0cargo, \u00a0tal \u00a0como \u00a0lo \u00a0exige \u00a0la \u00a0ley (art\u00edculo 212, ordinal 3\u00b0 del C\u00f3digo de \u00a0Procedimiento \u00a0Penal), \u00a0el \u00a0censor \u00a0no cumple con los restantes requisitos. Esto \u00a0es, no indica de forma clara y precisa los fundamentos del ataque. \u00a0\u00a0<\/p>\n<p>4.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La Corte ha se\u00f1alado de manera reiterada \u00a0la \u00a0relativa \u00a0sencillez \u00a0de \u00a0la \u00a0sustentaci\u00f3n \u00a0de \u00a0un \u00a0cargo de falso juicio de \u00a0identidad.\u00a0 \u00a0La \u00a0claridad \u00a0y \u00a0precisi\u00f3n \u00a0de los fundamentos del ataque que \u00a0exige \u00a0la \u00a0norma \u00a0procedimental, consiste en ser capaz de demostrar que el medio \u00a0probatorio \u00a0dice \u00a0una cosa y que el Juez le hizo decir una diferente.\u00a0 Pero \u00a0para \u00a0llegar \u00a0a \u00a0esa \u00a0demostraci\u00f3n, el cargo\u00a0 exige que el censor tenga un \u00a0conocimiento \u00a0concreto \u00a0de \u00a0lo que significa un falso juicio de identidad.\u00a0 \u00a0Ese \u00a0tipo \u00a0de \u00a0error, \u00a0como \u00a0ha \u00a0insistido la Corte, es de naturaleza objetiva y \u00a0ocurre \u00a0en \u00a0la \u00a0etapa \u00a0de la aprehensi\u00f3n material que el Juez hace de la prueba \u00a0como \u00a0objeto \u00a0de conocimiento.\u00a0 Esa es su esencia la de una tergiversaci\u00f3n \u00a0de \u00a0su \u00a0identidad, \u00a0entendida \u00a0\u00e9sta como la caracter\u00edstica propia de la prueba \u00a0que \u00a0la \u00a0hace ser lo que es y no otra cosa. Por contraste lo que el Juez hace al \u00a0incurrir \u00a0en el error es desidentificar el medio probatorio.\u00a0 El testimonio \u00a0como \u00a0medio \u00a0probatorio \u00a0es \u00a0lo que el testigo dice.\u00a0 Su ser es la versi\u00f3n \u00a0que \u00a0contiene, \u00a0en \u00a0la \u00a0concreta especificidad en que se relat\u00f3.\u00a0 Si en la \u00a0lectura \u00a0de \u00a0esa \u00a0versi\u00f3n se var\u00eda esa versi\u00f3n, se falsea su identidad.\u00a0 \u00a0En \u00a0tal \u00a0evento, \u00a0el relato aprehendido por el Juez es otro, uno\u00a0 que no se \u00a0identifica \u00a0con \u00a0el \u00a0que \u00a0existe \u00a0en \u00a0el \u00a0expediente.\u00a0 Por eso, la Corte ha \u00a0reiterado \u00a0 que \u00a0la \u00a0demostraci\u00f3n \u00a0se \u00a0obtiene \u00a0mediante \u00a0un \u00a0simple \u00a0ejercicio \u00a0comparativo \u00a0entre \u00a0lo \u00a0que \u00a0el \u00a0medio \u00a0probatorio dice y lo que el Juez la hizo \u00a0decir. \u00a0\u00a0<\/p>\n<p>5.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Todo \u00a0ello es justamente lo que pasa por \u00a0alto \u00a0el defensor de LUIS HONORIO MEJIA MARULANDA.\u00a0 Aunque formula un cargo \u00a0de \u00a0falso \u00a0juicio \u00a0de \u00a0identidad, \u00a0la \u00a0sustentaci\u00f3n \u00a0que \u00a0hace \u00a0no \u00a0es \u00a0la \u00a0que \u00a0corresponde \u00a0a \u00a0ese \u00a0tipo de cargo.\u00a0 Los fundamentos de la censura no ponen \u00a0de \u00a0presente \u00a0un \u00a0problema \u00a0de \u00a0apreciaci\u00f3n \u00a0material \u00a0de \u00a0la \u00a0prueba, sino una \u00a0discusi\u00f3n \u00a0 sobre \u00a0 el \u00a0m\u00e9rito \u00a0probatorio \u00a0que \u00a0el \u00a0Juez \u00a0le \u00a0asign\u00f3 \u00a0a \u00a0esa \u00a0prueba.\u00a0 \u00a0Esto \u00a0es, que no plantea un problema objetivo, como corresponde a \u00a0la \u00a0naturaleza \u00a0del error predicado, sino uno de tipo subjetivo, como quiera que \u00a0tiene \u00a0 origen \u00a0en \u00a0el \u00a0sujeto \u00a0(Juez) \u00a0de \u00a0la \u00a0proposici\u00f3n \u00a0valorativa \u00a0de \u00a0la \u00a0prueba. \u00a0\u00a0<\/p>\n<p>6.- \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Pero \u00a0si se pasara por alto el requisito \u00a0formal \u00a0de \u00a0la \u201cformulaci\u00f3n del cargo\u201d (ordinal 3\u00b0 del art\u00edculo 212) y se \u00a0entendiera \u00a0que \u00a0el \u00a0censor \u00a0se refiere simple y llanamente a un error de hecho, \u00a0a\u00fan \u00a0as\u00ed \u00a0la \u00a0demanda \u00a0tambi\u00e9n \u00a0debe \u00a0ser inadmitida. Tal conclusi\u00f3n resulta \u00a0clara \u00a0cuando \u00a0se advierte que el tipo de critica probatoria que hace el censor, \u00a0es \u00a0compatible \u00a0con \u00a0un \u00a0alegato \u00a0de \u00a0instancia, \u00a0pero \u00a0inadmisible \u00a0en \u00a0sede de \u00a0casaci\u00f3n. \u00a0La presunci\u00f3n de legalidad y acierto de sentencias que han superado \u00a0el \u00a0control \u00a0de \u00a0las instancias, impone que el an\u00e1lisis probatorio en casaci\u00f3n \u00a0no \u00a0sea \u00a0la \u00a0simple expresi\u00f3n de las opiniones estimativas del demandante, sino \u00a0el \u00a0se\u00f1alamiento \u00a0claro \u00a0y \u00a0preciso \u00a0de \u00a0un \u00a0error \u00a0y de su trascendencia en la \u00a0producci\u00f3n del fallo. \u00a0\u00a0<\/p>\n<p>Nada \u00a0de \u00a0ello hace el censor. Del testimonio \u00a0transcribe \u00a0algunos \u00a0apartes y de ellos extrae sus conclusiones, pero no se\u00f1ala \u00a0por \u00a0qu\u00e9 \u00a0debe \u00a0preferirse \u00a0ese \u00a0an\u00e1lisis \u00a0en \u00a0desmedro \u00a0del \u00a0contenido \u00a0en el \u00a0fallo.\u00a0 \u00a0No se\u00f1ala ninguna infracci\u00f3n a las reglas de la sana cr\u00edtica, o \u00a0problema \u00a0alguno \u00a0de \u00a0legalidad \u00a0o de tergiversaci\u00f3n material de alguna prueba. \u00a0No, \u00a0simplemente \u00a0se \u00a0trata \u00a0de \u00a0una \u00a0disparidad \u00a0de \u00a0criterios \u00a0entre \u00e9l y los \u00a0Juzgadores, \u00a0 conflicto \u00a0que \u00a0est\u00e1 \u00a0resuelto \u00a0de \u00a0antemano \u00a0por \u00a0virtud \u00a0de \u00a0la \u00a0presunci\u00f3n de legalidad y acierto de la decisi\u00f3n que se ataca.. \u00a0\u00a0<\/p>\n<p>A \u00a0juicio \u00a0del \u00a0censor \u00a0el \u00a0testimonio \u00a0de la \u00a0se\u00f1ora \u00a0Luz \u00a0Mery \u00a0Ospina Suaza no puede ser tenido como cre\u00edble por raz\u00f3n de \u00a0los \u00a0sentimientos \u00a0de odio que ella albergaba en contra del procesado.\u00a0 Ese \u00a0supuesto \u00a0odio, \u00a0dice \u00a0que \u00a0surge \u00a0de la iniciaci\u00f3n por parte de ella de nuevas \u00a0relaciones \u00a0sentimentales \u00a0que \u00a0determinaban \u00a0la \u00a0exclusi\u00f3n \u00a0de \u00a0la \u00a0que hab\u00eda \u00a0mantenido \u00a0con \u00a0el \u00a0acusado \u00a0y \u00a0con \u00a0quien ten\u00eda una hija en com\u00fan.\u00a0 Esas \u00a0afirmaciones \u00a0son \u00a0claramente \u00a0ejemplificables \u00a0de un alegato de instancia, pero \u00a0inaceptables \u00a0 para \u00a0sustentar \u00a0una \u00a0demanda \u00a0de \u00a0casaci\u00f3n. \u00a0No \u00a0hay \u00a0all\u00ed \u00a0el \u00a0se\u00f1alamiento \u00a0concreto \u00a0de un error.\u00a0 Se trata de un discurso que pretende \u00a0convencer \u00a0a \u00a0la \u00a0Corte de la conveniencia de preferir la estimaci\u00f3n probatoria \u00a0que \u00a0el \u00a0censor \u00a0hace \u00a0de \u00a0un \u00a0testimonio \u00a0en \u00a0desmedro \u00a0de \u00a0la que hicieron los \u00a0Juzgadores.\u00a0 \u00a0Tal \u00a0posici\u00f3n \u00a0es inaceptable.\u00a0 El recurso de casaci\u00f3n \u00a0es \u00a0estrictamente \u00a0asertivo.\u00a0 \u00a0Se trata de demostrar no de convencer.\u00a0 \u00a0El \u00a0error \u00a0debe \u00a0existir \u00a0y ser trascendente. Esas situaciones deben demostrarse \u00a0bajo \u00a0condiciones \u00a0de suficiencia y necesidad.\u00a0 Como ello no ocurri\u00f3 en la \u00a0demanda \u00a0 que \u00a0 suscribe \u00a0el \u00a0defensor \u00a0de \u00a0LUIS \u00a0HONORIO \u00a0MEJIA \u00a0MARULANDA, \u00a0se \u00a0inadmitir\u00e1. \u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, La Corte Suprema de \u00a0Justicia, Sala de Casaci\u00f3n Penal, \u00a0\u00a0<\/p>\n<p>R E S U E L V E \u00a0<\/p>\n<p>PRIMERO: \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0INADMITIR la demanda de casaci\u00f3n \u00a0presentada \u00a0 \u00a0por \u00a0 \u00a0el \u00a0 \u00a0defensor \u00a0 \u00a0del \u00a0 \u00a0procesado \u00a0 LUIS \u00a0 HONORIO \u00a0 MEJIA \u00a0MARULANDA. \u00a0\u00a0<\/p>\n<p>SEGUNDO: \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Declarar \u00a0desierto el recurso de \u00a0casaci\u00f3n \u00a0 concedido \u00a0 por \u00a0el \u00a0Tribunal \u00a0Superior \u00a0del \u00a0Distrito \u00a0Judicial \u00a0de \u00a0Medell\u00edn. \u00a0\u00a0<\/p>\n<p>TERCERO: \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Contra \u00a0la presente decisi\u00f3n no \u00a0procede recurso alguno. Devu\u00e9lvase al Tribunal de origen. \u00a0\u00a0<\/p>\n<p>CUMPLASE \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>ALVARO ORLANDO PEREZ PINZON \u00a0<\/p>\n<p>FERNANDO \u00a0 ARBOLEDA \u00a0 RIPOLL \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 JORGE E. \u00a0CORDOBA POVEDA \u00a0\u00a0<\/p>\n<p>HERMAN \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0GALAN \u00a0CASTELLANOS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0CARLOS A. GALVEZ ARGOTE \u00a0\u00a0<\/p>\n<p>JORGE \u00a0 \u00a0 \u00a0 \u00a0 A. \u00a0 \u00a0 \u00a0 \u00a0 GOMEZ \u00a0GALLEGO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0EDGAR LOMBANA TRUJILLO \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 \u00a0 \u00a0 \u00a0 E. \u00a0 \u00a0 \u00a0 \u00a0MEJIA \u00a0ESCOBAR\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0NILSON PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>TERESA RUIZ NU\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 14903 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACION PENAL \u00a0 Magistrado Ponente \u00a0 Dr. Carlos E. Mej\u00eda Escobar \u00a0 Aprobado\u00a0 Acta No. 62 \u00a0 Bogot\u00e1 \u00a0D.C.,\u00a0 \u00a0trece\u00a0 \u00a0(13)\u00a0 \u00a0de\u00a0 \u00a0 junio\u00a0\u00a0 \u00a0de\u00a0 \u00a0dos\u00a0 \u00a0mil\u00a0 \u00a0dos\u00a0 \u00a0(2002). \u00a0\u00a0 V\u00a0 \u00a0I\u00a0 \u00a0S\u00a0 \u00a0T\u00a0 \u00a0O\u00a0 \u00a0S\u00a0 \u00a0\u00a0 Resuelve la Sala lo que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5658","post","type-post","status-publish","format-standard","hentry","category-10"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/5658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=5658"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/5658\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=5658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=5658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=5658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}