{"id":5558,"date":"2023-09-08T16:23:34","date_gmt":"2023-09-08T16:23:34","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1406521-11-02\/"},"modified":"2023-09-08T16:23:34","modified_gmt":"2023-09-08T16:23:34","slug":"1406521-11-02","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1406521-11-02\/","title":{"rendered":"14065(21-11-02)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 14065 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CORTE SUPREMA DE JUSTICIA \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0SALA DE CASACION PENAL \u00a0\u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>Dr. \u00a0FERNANDO \u00a0E. \u00a0ARBOLEDA RIPOLL \u00a0\u00a0<\/p>\n<p>Aprobado \u00a0 \u00a0 \u00a0 \u00a0acta \u00a0 \u00a0 \u00a0 \u00a0No. \u00a0149\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1, D. C.,\u00a0 veintiuno de noviembre \u00a0del a\u00f1o dos mil dos. \u00a0\u00a0<\/p>\n<p>Resuelve \u00a0la Corte el recurso extraordinario \u00a0de \u00a0casaci\u00f3n \u00a0interpuesto \u00a0por \u00a0los \u00a0defensores \u00a0de los procesados MIGUEL \u00a0ANTONIO\u00a0 \u00a0CABRERA \u00a0G\u00d3MEZ, \u00a0URIEL MONROY y EDGAR ARIAS \u00a0OROZCO \u00a0contra \u00a0la \u00a0sentencia dictada por el Tribunal \u00a0nacional \u00a0mediante \u00a0la \u00a0cual \u00a0los \u00a0conden\u00f3 por el delito de secuestro extorsivo \u00a0agravado. \u00a0\u00a0<\/p>\n<p>Hechos \u00a0y \u00a0actuaci\u00f3n procesal.- \u00a0\u00a0<\/p>\n<p>1.-\u00a0 \u00a0Aquellos\u00a0 \u00a0fueron declarados \u00a0por el juzgador de la manera siguiente: \u00a0\u00a0<\/p>\n<p>\u201cD\u00edas \u00a0antes \u00a0del \u00a0cinco \u00a0de \u00a0mayo \u00a0del \u00a0presente \u00a0a\u00f1o (1993), EDGAR ARIAS OROZCO, residente en el municipio de Girardot \u00a0(Cund.), \u00a0alegando \u00a0estar \u00a0en \u00a0dificultades \u00a0econ\u00f3micas, comunic\u00f3 a sus amigas \u00a0MIRTHA \u00a0P\u00c9REZ \u00a0PULECIO y JANETH SUSANA JIM\u00c9NEZ V\u00c1SQUEZ\u00a0 su intenci\u00f3n de \u00a0secuestrar \u00a0al \u00a0menor \u00a0JOHN JAIRO ARIAS MU\u00d1OZ, hijo de su hermano JUAN BAUTISTA \u00a0ARIAS, \u00a0vecino de Santa Rosa de cabal; que necesitaba de su ayuda por lo que les \u00a0ofreci\u00f3 \u00a0algunos millones de pesos de los doscientos que hab\u00eda de pedir por el \u00a0rescate \u00a0del \u00a0menor. \u00a0Aceptada que fue la oferta por las dos mujeres se vincul\u00f3 \u00a0igualmente \u00a0a \u00a0tomar \u00a0parte \u00a0en \u00a0la empresa criminal a ESTELLA CULLMAN JIM\u00c9NEZ, \u00a0amiga \u00a0\u00edntima \u00a0de \u00a0MIRTHA, \u00a0URIEL \u00a0MONROY, \u00a0yerno \u00a0de la misma y MIGUEL ANTONIO \u00a0CABRERA \u00a0G\u00d3MEZ, \u00a0quienes \u00a0desde \u00a0un principio y bajo la direcci\u00f3n de EDGAR, se \u00a0dedicaron \u00a0a la planeaci\u00f3n de su criminal cometido, para lo cual se trasladaron \u00a0algunos \u00a0miembros \u00a0de la banda hasta Santa Rosa de Cabal donde fue localizada la \u00a0v\u00edctima, \u00a0 su \u00a0 residencia, \u00a0as\u00ed \u00a0como \u00a0el \u00a0colegio \u00a0donde \u00a0estudiaba. \u00a0Siendo \u00a0aproximadamente \u00a0la \u00a0una de la tarde del 5 de mayo \u00faltimo pasado, y en momentos \u00a0en \u00a0que JOHN JAIRO ARIAS MU\u00d1OZ, de 12 a\u00f1os de edad se dispon\u00eda a entrar a las \u00a0instalaciones \u00a0estudiantiles, \u00a0fue \u00a0abordado \u00a0por JANETH SUSANA y MIRTHA quienes \u00a0fingiendo \u00a0amistad \u00a0lo \u00a0condujeron hasta un lugar cercano donde los esperaba una \u00a0tercera \u00a0persona \u00a0de \u00a0sexo \u00a0masculino no identificada en autos y quien conduc\u00eda \u00a0una \u00a0motocicleta, \u00a0la cual convenci\u00f3 al ni\u00f1o para que las acompa\u00f1ara toda vez \u00a0que \u00a0su \u00a0padre \u00a0hab\u00eda sido gravemente herido. Despu\u00e9s de hacer un largo viaje, \u00a0primero \u00a0en \u00a0la \u00a0motocicleta, \u00a0luego \u00a0en \u00a0bus \u00a0y al final nuevamente en moto, la \u00a0v\u00edctima \u00a0fue \u00a0llevada \u00a0en \u00a0primera \u00a0instancia a Ibagu\u00e9 para posteriormente ser \u00a0trasladado \u00a0a \u00a0la \u00a0ciudad \u00a0de \u00a0Neiva, \u00a0en \u00a0donde \u00a0se \u00a0qued\u00f3 \u00a0bajo \u00a0el cuidado y \u00a0vigilancia \u00a0de \u00a0JANETH \u00a0SUSANA y ESTELLA CULLMAN JIM\u00c9NEZ, las que esperaban las \u00a0\u00f3rdenes \u00a0de \u00a0los \u00a0dem\u00e1s \u00a0miembros \u00a0de la banda, los que desde esa fecha dieron \u00a0principio \u00a0a \u00a0la exigencia de doscientos millones de pesos para poder liberar al \u00a0menor sano y salvo. \u00a0\u00a0<\/p>\n<p>\u201cIniciada la investigaci\u00f3n se dio aviso a \u00a0la \u00a0Unidad \u00a0Antiextorsi\u00f3n \u00a0y \u00a0Secuestro \u00a0UNASE \u00a0de la ciudad de Pereira, la que \u00a0organiz\u00f3 \u00a0un \u00a0operativo especial a fin de detectar el lugar de donde se ven\u00edan \u00a0originando \u00a0las \u00a0llamadas \u00a0telef\u00f3nicas al padre del menor, dando como resultado \u00a0la \u00a0retenci\u00f3n \u00a0en \u00a0flagrancia en la ciudad de Ibagu\u00e9 de MIGUEL ANTONIO CABRERA \u00a0G\u00d3MEZ \u00a0cuando \u00a0realizaba \u00a0una \u00a0de las llamadas, as\u00ed como la de MIRTHA P\u00c9REZ y \u00a0URIEL \u00a0MONROY \u00a0que \u00a0lo esperaban en una motocicleta en el exterior de la oficina \u00a0de \u00a0telecomunicaciones. \u00a0Acto \u00a0seguido, \u00a0los \u00a0agentes \u00a0se trasladaron a NEIVA en \u00a0donde \u00a0liberaron \u00a0al \u00a0secuestrado \u00a0y \u00a0capturaron \u00a0a \u00a0las \u00a0mujeres \u00a0JANETH SUSANA \u00a0JIM\u00c9NEZ \u00a0y \u00a0ESTELLA \u00a0CULLMAN \u00a0JIM\u00c9NEZ encargadas de cuidar a la v\u00edctima, para \u00a0luego \u00a0ir a la ciudad de Girardot donde se captur\u00f3 a EDGAR ARIAS OROZCO, mentor \u00a0del acto criminal\u201d. \u00a0\u00a0<\/p>\n<p>2.- \u00a0Iniciada \u00a0la \u00a0investigaci\u00f3n \u00a0por \u00a0la \u00a0Fiscal\u00eda \u00a0treinta \u00a0y \u00a0uno \u00a0seccional con sede en Santa Rosa de Cabal -Risaralda \u00a0(fl. \u00a03), \u00a0vincul\u00f3 mediante indagatoria a CECILIA TORRES ROLDAN (fl. 6 vto.), a \u00a0quien \u00a0 defini\u00f3 \u00a0 su \u00a0situaci\u00f3n \u00a0jur\u00eddica \u00a0con \u00a0medida \u00a0de \u00a0aseguramiento \u00a0de \u00a0detenci\u00f3n \u00a0preventiva \u00a0(fls. \u00a013 y ss.), posteriormente revocada a solicitud de \u00a0la defensa y el Ministerio p\u00fablico (fls. 203 y ss.). \u00a0\u00a0<\/p>\n<p>D\u00edas m\u00e1s tarde, el conocimiento del asunto \u00a0lo \u00a0asumi\u00f3 una Fiscal\u00eda regional con sede en Medell\u00edn (fl. 43), autoridad que \u00a0vincul\u00f3 \u00a0mediante \u00a0indagatoria \u00a0a \u00a0MIGUEL \u00a0ANTONIO CABRERA G\u00d3MEZ (fl. 88 y 153 \u00a0ss.), \u00a0MIRTHA \u00a0P\u00c9REZ \u00a0PULECIO \u00a0(fls. \u00a091 \u00a0y ss.), URIEL MONROY (fls. 95 y ss.), \u00a0JANETH \u00a0SUSANA \u00a0JIM\u00c9NEZ \u00a0V\u00c1SQUEZ (fl. 100), ESTELLA CULLMAN JIM\u00c9NEZ (fl. 103) \u00a0y\u00a0 \u00a0EDGAR \u00a0ARIAS \u00a0OROZCO (fls. 109 y ss.), a quienes defini\u00f3 su situaci\u00f3n \u00a0jur\u00eddica \u00a0con \u00a0medida \u00a0de \u00a0aseguramiento \u00a0de \u00a0detenci\u00f3n preventiva (fls. 161 y \u00a0ss.). \u00a0\u00a0<\/p>\n<p>Posteriormente, \u00a0previa \u00a0clausura \u00a0del ciclo \u00a0instructivo \u00a0(fl. \u00a0293), el veintid\u00f3s de noviembre de mil novecientos noventa y \u00a0tres \u00a0se \u00a0calific\u00f3 el m\u00e9rito probatorio del sumario profiriendo resoluci\u00f3n de \u00a0acusaci\u00f3n \u00a0en \u00a0contra \u00a0de \u00a0los \u00a0procesados \u00a0EDGAR \u00a0ARIAS \u00a0OROZCO, MIRTHA P\u00c9REZ \u00a0PULECIO, \u00a0JANETH SUSANA JIM\u00c9NEZ V\u00c1SQUEZ, STELLA CULLMAN JIM\u00c9NEZ, URIEL MONROY \u00a0y \u00a0MIGUEL \u00a0ANTONIO CABRERA G\u00d3MEZ por el delito de secuestro extorsivo-agravado, \u00a0al \u00a0tiempo \u00a0que \u00a0precluy\u00f3 \u00a0la \u00a0investigaci\u00f3n respecto de GLORIA CECILIA TORRES \u00a0ROLD\u00c1N \u00a0(fls. \u00a0362 y ss.), mediante determinaci\u00f3n que el trece de abril de mil \u00a0novecientos \u00a0noventa \u00a0y \u00a0cuatro \u00a0la Fiscal\u00eda delegada ante el Tribunal nacional \u00a0confirm\u00f3 \u00a0\u00edntegramente \u00a0al \u00a0conocer \u00a0de \u00a0la \u00a0apelaci\u00f3n \u00a0interpuesta por URIEL \u00a0MONROY (fls. 545 y ss). \u00a0\u00a0<\/p>\n<p>3.- \u00a0El \u00a0conocimiento del juicio fue asumido \u00a0por \u00a0un \u00a0Juzgado \u00a0regional \u00a0de \u00a0Medell\u00edn (fl. 2 cno. 2), donde previa citaci\u00f3n \u00a0para \u00a0 proferir \u00a0 sentencia \u00a0(fl. \u00a0335), \u00a0el \u00a0veintid\u00f3s \u00a0de \u00a0noviembre \u00a0de \u00a0mil \u00a0novecientos \u00a0noventa \u00a0y \u00a0cinco \u00a0se \u00a0puso \u00a0fin \u00a0a \u00a0la \u00a0instancia condenando a los \u00a0procesados \u00a0MIGUEL \u00a0ANTONIO CABRERA G\u00d3MEZ, URIEL MONROY, MIRTHA P\u00c9REZ PULECIO, \u00a0JANETH \u00a0SUSANA \u00a0JIM\u00c9NEZ \u00a0V\u00c1SQUEZ \u00a0y \u00a0ESTELLA \u00a0CULLMAN \u00a0JIM\u00c9NEZ \u00a0a \u00a0las \u00a0penas \u00a0principales \u00a0de \u00a0cuarenta \u00a0y cinco (45) a\u00f1os de prisi\u00f3n y multa en cuant\u00eda de \u00a0doscientos \u00a0(200) \u00a0salarios \u00a0m\u00ednimos \u00a0legales \u00a0mensuales; conden\u00f3 al procesado \u00a0EDGAR \u00a0ARIAS \u00a0OROZCO \u00a0a \u00a0las penas principales de cincuenta y tres (53) a\u00f1os de \u00a0prisi\u00f3n \u00a0y \u00a0multa \u00a0en cuant\u00eda equivalente a doscientos (200) salarios m\u00ednimos \u00a0legales \u00a0mensuales; \u00a0y \u00a0a todos ellos a la pena accesoria de interdicci\u00f3n en el \u00a0ejercicio \u00a0de derechos y funciones p\u00fablicas por el t\u00e9rmino de diez (10) a\u00f1os, \u00a0a \u00a0consecuencia de declararlos penalmente responsables del delito imputado en el \u00a0pliego \u00a0enjuiciatorio \u00a0(fls. \u00a05 \u00a0y \u00a0ss. \u00a0-3), \u00a0mediante sentencia que el doce de \u00a0agosto \u00a0de \u00a0mil \u00a0novecientos noventa y seis el Tribunal nacional modific\u00f3 en lo \u00a0relativo \u00a0al \u00a0procesado \u00a0EDGAR \u00a0ARIAS OROZCO a quien fij\u00f3 cuarenta y cinco (45) \u00a0a\u00f1os \u00a0de prisi\u00f3n; adicion\u00f3 en el sentido de condenar a los procesados al pago \u00a0en \u00a0concreto \u00a0de \u00a0los da\u00f1os y perjuicios morales ocasionados por el punible, en \u00a0cuant\u00eda \u00a0equivalente \u00a0a \u00a0trescientos \u00a0gramos \u00a0oro, y confirm\u00f3 en sus restantes \u00a0partes \u00a0(fls. \u00a03 y ss. cno. Trib.), al conocer en segunda instancia por v\u00eda del \u00a0grado \u00a0 jurisdiccional \u00a0 de \u00a0consulta \u00a0y \u00a0de \u00a0la \u00a0apelaci\u00f3n \u00a0promovida \u00a0por \u00a0la \u00a0defensa. \u00a0\u00a0<\/p>\n<p>4.- \u00a0Contra \u00a0el \u00a0fallo \u00a0de segundo grado, en \u00a0oportunidad, \u00a0los \u00a0procesados \u00a0MIRTHA \u00a0P\u00c9REZ \u00a0PULECIO \u00a0(fl. \u00a035), JANETH SUSANA \u00a0JIM\u00c9NEZ \u00a0V\u00c1SQUEZ\u00a0 \u00a0(fl. \u00a036), \u00a0EDGAR ARIAS OROZCO (fl. 135),\u00a0 MIGUEL \u00a0ANTONIO \u00a0CABRERA \u00a0G\u00d3MEZ \u00a0(fl. \u00a0132),\u00a0 \u00a0STELLA CULLMAN JIM\u00c9NEZ (fl. 145) y \u00a0URIEL \u00a0MONROY \u00a0(fl. \u00a0135), y sus defensores interpusieron recurso extraordinario \u00a0de \u00a0casaci\u00f3n \u00a0(fls. \u00a038, \u00a037 y 131), el cual fue concedido por el ad quem (fls. \u00a0147) \u00a0y \u00a0dentro \u00a0del \u00a0t\u00e9rmino \u00a0legal \u00a0los defensores de EDGAR ARIAS OROZCO (fl. \u00a0169), \u00a0MIGUEL \u00a0ANTONIO \u00a0CABRERA \u00a0G\u00d3MEZ \u00a0(fl. \u00a0186) \u00a0y \u00a0URIEL MONROY (fls. 231), \u00a0presentaron \u00a0 los \u00a0correspondientes \u00a0escritos \u00a0sustentatorios \u00a0que \u00a0se \u00a0declar\u00f3 \u00a0ajustados \u00a0a \u00a0las \u00a0prescripciones \u00a0legales \u00a0por \u00a0la \u00a0Sala (fl. 3 cno. Corte), no \u00a0aconteciendo \u00a0igual \u00a0respecto \u00a0de \u00a0las \u00a0procesadas MIRTHA P\u00c9REZ PULECIO, JANETH \u00a0SUSANA \u00a0JIM\u00c9NEZ \u00a0V\u00c1SQUEZ\u00a0 \u00a0y \u00a0STELLA \u00a0CULLMAN \u00a0JIM\u00c9NEZ \u00a0cuyo recurso fue \u00a0declarado desierto por el Tribunal (fl. 252). \u00a0\u00a0<\/p>\n<p>Las \u00a0 \u00a0 \u00a0 demandas.-\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>1.- \u00a0A nombre del \u00a0procesado EDGAR ARIAS OROZCO. \u00a0\u00a0<\/p>\n<p>UNICO CARGO. (Violaci\u00f3n directa de normas de \u00a0derecho sustancial). \u00a0\u00a0<\/p>\n<p>Apoyado en la causal primera de casaci\u00f3n, un \u00a0cargo \u00a0postula el demandante contra el fallo del Tribunal en el que denuncia que \u00a0es \u00a0 directamente \u00a0 violatorio \u00a0 de \u00a0 disposiciones \u00a0 de \u00a0 derecho \u00a0 sustancial, \u00a0concretamente \u00a0de los art\u00edculos 29 de la Carta Pol\u00edtica, 5\u00ba del C\u00f3digo penal \u00a0de \u00a01980, \u00a0247, \u00a0253, \u00a0254, 294, 445 y 446 del C\u00f3digo de procedimiento penal de \u00a01991, \u00a0\u201cnormas \u00a0que \u00a0garantizan la PRESUNCI\u00d3N DE INOCENCIA y materializan los \u00a0requisitos \u00a0para \u00a0edificar \u00a0la responsabilidad penal, sin que se vislumbre en lo \u00a0m\u00e1s \u00a0m\u00ednimo \u00a0una \u00a0responsabilidad objetiva, teniendo en cuenta adem\u00e1s que las \u00a0pruebas \u00a0se \u00a0deben valorar en conjunto, siguiendo rigurosamente las reglas de la \u00a0sana \u00a0cr\u00edtica \u00a0y destacando adem\u00e1s, que para que halla (sic) debate probatorio \u00a0es \u00a0necesario \u00a0y fundamental practicar las pruebas en el juicio, m\u00e1s si tenemos \u00a0en \u00a0cuenta \u00a0que \u00a0esta \u00a0jurisdicci\u00f3n viola ostensiblemente las reglas del debido \u00a0proceso\u201d. \u00a0\u00a0<\/p>\n<p>Sostiene \u00a0que \u00a0al \u00a0procesado \u00a0se le conden\u00f3 \u00a0\u00fanica \u00a0y \u00a0exclusivamente \u00a0con \u00a0fundamento \u00a0en las versiones rendidas por MIRTHA \u00a0P\u00c9REZ \u00a0PULECIO, \u00a0STELLA \u00a0CULLMAN \u00a0JIM\u00c9NEZ \u00a0y \u00a0JANETH SUSANA JIM\u00c9NEZ V\u00c1SQUEZ, \u00a0\u201cporque \u00a0as\u00ed \u00a0lo \u00a0dijeron, \u00a0pero \u00a0cuando \u00a0ya hab\u00edan sido capturados y con un \u00a0compromiso profundo en el reato\u201d. \u00a0\u00a0<\/p>\n<p>La \u00a0afirmaci\u00f3n \u00a0de \u00a0que \u00a0su asistido fue el \u00a0mentor \u00a0de \u00a0la idea criminal, carece de respaldo en la realidad, dado que no fue \u00a0confirmada \u00a0por \u00a0una \u00a0prueba \u00a0directa, sino por v\u00eda del silogismo indiciario en \u00a0que \u00a0siempre \u00a0se \u00a0mantuvo \u00a0su \u00a0responsabilidad. \u00a0\u201cPor \u00a0lo tanto, agrega, se ha \u00a0presentado \u00a0en \u00a0forma \u00a0indirecta, \u00a0un \u00a0vulneramiento de las normas procesales de \u00a0derecho \u00a0penal, por existencia de errores de apreciaci\u00f3n de hechos y de derecho \u00a0de contenido y naturaleza eminentemente probatorio\u201d. \u00a0\u00a0<\/p>\n<p>Afirma \u00a0que \u00a0los \u00a0juzgadores \u00a0no tuvieron en \u00a0cuenta \u00a0las \u00a0explicaciones \u00a0del procesado, ni las circunstancias en que el hecho \u00a0tuvo \u00a0realizaci\u00f3n, \u00a0pues \u00a0se \u00a0se\u00f1ala \u00a0la existencia de un plan sin que se sepa \u00a0cu\u00e1ndo \u00a0se \u00a0llev\u00f3 \u00a0a \u00a0cabo, \u00a0ya \u00a0que \u00a0quienes \u00a0lo \u00a0ejecutaron \u00a0fueron personas \u00a0distintas de su asistido. \u00a0\u00a0<\/p>\n<p>Considera \u00a0que \u00a0el \u00a0tribunal \u00a0no concreta la \u00a0prueba \u00a0de \u00a0responsabilidad \u00a0penal, \u00a0\u201cpues \u00a0aqu\u00ed \u00a0se \u00a0present\u00f3 una alianza y \u00a0solidaridad \u00a0de \u00a0las 3 mujeres condenadas para incriminar a mi defendido\u201d, sin \u00a0que \u00a0se \u00a0hubiere \u00a0probado \u00a0cu\u00e1ndo \u00a0se plane\u00f3 el secuestro ni la injerencia que \u00a0tuvo el procesado. \u00a0\u00a0<\/p>\n<p>Se afirm\u00f3 tan s\u00f3lo, que EDGAR ARIAS OROZCO \u00a0era \u00a0t\u00edo \u00a0del menor secuestrado, lo conoc\u00eda y sab\u00eda de sus padres, pero no se \u00a0verific\u00f3 \u00a0 \u00a0lo \u00a0 \u00a0anterior \u00a0 \u00a0ni \u00a0 \u00a0se \u00a0 comprob\u00f3 \u00a0 que \u00a0 particip\u00f3 \u00a0 en \u00a0 el \u00a0secuestro. \u00a0\u00a0<\/p>\n<p>Los juzgadores de instancia fundamentaron la \u00a0decisi\u00f3n \u00a0de \u00a0condena \u00a0en \u00a0declaraciones \u00a0contradictorias \u00a0de \u00a0las \u00a0mencionadas \u00a0mujeres, \u00a0que \u00a0se \u00a0enfrentan \u00a0a \u00a0las \u00a0exposiciones \u00a0de \u00a0los \u00a0otros procesados, y \u00a0analizan \u00a0la \u00a0prueba s\u00f3lo desde un \u00e1ngulo contraviniendo las reglas del debido \u00a0proceso \u00a0y \u00a0las \u00a0establecidas \u00a0en \u00a0el art\u00edculo 253 del C\u00f3digo de procedimiento \u00a0penal de 1991. \u00a0\u00a0<\/p>\n<p>Esta \u00a0 sobrevaloraci\u00f3n \u00a0 de \u00a0las \u00a0fuentes \u00a0indiciarias, \u00a0 conllev\u00f3 \u00a0 a \u00a0 dar \u00a0 por \u00a0acreditado \u00a0en \u00a0grado \u00a0de \u00a0certeza \u00a0la \u00a0responsabilidad \u00a0 penal \u00a0 a \u00a0pesar \u00a0de \u00a0carecer \u00a0de \u00a0los \u00a0elementos \u00a0probatorios \u00a0suficientes \u00a0para \u00a0sustentar una decisi\u00f3n de condena, pues la situaci\u00f3n en que \u00a0se \u00a0 encontraban \u00a0las \u00a0mujeres, \u00a0imped\u00eda \u00a0que \u00a0su \u00a0testimonio \u00a0fuera \u00a0objetivo, \u00a0imparcial y que ofreciera credibilidad. \u00a0\u00a0<\/p>\n<p>Se afirm\u00f3 en el fallo que con posterioridad \u00a0al \u00a0secuestro \u00a0EDGAR ARIAS OROZCO manten\u00eda informados a MIRTHA P\u00c9REZ y a URIEL \u00a0MONROY, \u00a0cuando \u00a0lo \u00a0cierto \u00a0es \u00a0que \u00a0\u00e9ste \u00a0no \u00a0conoci\u00f3 a aqu\u00e9l, y adem\u00e1s se \u00a0encontraba \u00a0 \u00a0en \u00a0 \u00a0lugar \u00a0 \u00a0distante \u00a0 \u00a0de \u00a0 \u00a0donde \u00a0 \u00a0los \u00a0 \u00a0hechos \u00a0 tuvieron \u00a0realizaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Sostiene que el fallo incurre en falso juicio \u00a0de \u00a0identidad \u00a0en \u00a0relaci\u00f3n \u00a0con la prueba recaudada, pues la plena prueba para \u00a0condenar \u00a0no \u00a0se \u00a0halla \u00a0reunida \u00a0en \u00a0el \u00a0proceso \u201cpor el abundante c\u00famulo de \u00a0hip\u00f3tesis, \u00a0de \u00a0conjeturaciones (sic), que se deben practicar para llegar a una \u00a0u otra conclusi\u00f3n\u201d. \u00a0\u00a0<\/p>\n<p>Asimismo \u00a0carece de fundamento probatorio en \u00a0lo \u00a0relacionado \u00a0con la autor\u00eda intelectual del hecho, pues tal apreciaci\u00f3n se \u00a0apoy\u00f3 \u00a0 en \u00a0 un \u00a0 supuesto \u00a0estado \u00a0de \u00a0necesidad \u00a0econ\u00f3mica \u00a0que \u00a0tampoco \u00a0se \u00a0estableci\u00f3. \u00a0\u00a0<\/p>\n<p>\u201cEn \u00a0resumidas \u00a0cuentas \u00a0se \u00a0le otorg\u00f3 un \u00a0profundo \u00a0m\u00e9rito, \u00a0a \u00a0unos \u00a0medios \u00a0de \u00a0prueba, \u00a0m\u00e1s \u00a0que \u00a0a \u00a0otros, \u00a0as\u00ed \u00a0lo \u00a0desfavorable \u00a0se \u00a0tuvo \u00a0en \u00a0cuenta \u00a0y \u00a0se \u00a0desech\u00f3 \u00a0lo \u00a0favorable, \u00a0las pruebas \u00a0recaudadas \u00a0no \u00a0re\u00fanen los requisitos exigidos por el precepto que establece su \u00a0ritual \u00a0ceremonial, \u00a0porque \u00a0entre otras cosas se le ha atribuido un valor legal \u00a0que no merecen y por lo tanto que no le corresponden\u201d. \u00a0\u00a0<\/p>\n<p>De \u00a0la prueba recaudada en el proceso lo que \u00a0surge \u00a0es \u00a0la \u00a0duda \u00a0e \u00a0incertidumbre, raz\u00f3n por la cual el fallo ha debido ser \u00a0absolutorio \u00a0en \u00a0aplicaci\u00f3n \u00a0de los principios de presunci\u00f3n de inocencia e in \u00a0dubio \u00a0pro \u00a0reo, \u00a0m\u00e1xime \u00a0si \u00a0la \u00a0etapa \u00a0de juicio se llev\u00f3 a cabo sin allegar \u00a0pruebas \u00a0distintas \u00a0de \u00a0las \u00a0recaudadas \u00a0en \u00a0la \u00a0fase \u00a0de instrucci\u00f3n\u00a0 con \u00a0transgresi\u00f3n del derecho de defensa y el debido proceso. \u00a0\u00a0<\/p>\n<p>Con fundamento en lo anterior solicita de la \u00a0Corte\u00a0 \u00a0casar \u00a0la sentencia acusada, y absolver a su asistido de los cargos \u00a0formulados \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (fls. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 169 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 ss. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0cno. \u00a0trib.).\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>2.- \u00a0A nombre del \u00a0procesado MIGUEL ANTONIO CABRERA G\u00d3MEZ. \u00a0\u00a0<\/p>\n<p>UNICO \u00a0CARGO \u00a0(Violaci\u00f3n \u00a0del \u00a0derecho \u00a0de \u00a0defensa). \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Con apoyo en la causal tercera de casaci\u00f3n, \u00a0un \u00a0cargo postula el demandante contra el fallo del Tribunal, en el que denuncia \u00a0que \u00a0fue \u00a0proferido \u00a0en \u00a0juicio viciado de nulidad por violaci\u00f3n del derecho de \u00a0defensa. \u00a0\u00a0<\/p>\n<p>Sostiene que la pretensi\u00f3n invalidatoria del \u00a0proceso \u00a0se \u00a0soporta, \u00a0en primer lugar, en que su asistido careci\u00f3 de asesor\u00eda \u00a0jur\u00eddica \u00a0profesional \u00a0id\u00f3nea, \u00a0pues \u00a0a \u00a0pesar \u00a0de haber contado con supuestos \u00a0apoderados \u00a0judiciales, \u00a0su \u00a0inactividad \u00a0resulta \u00a0palmaria, sin que tal actitud \u00a0pueda \u00a0ser \u00a0asumida \u00a0como estrategia defensiva, y en segundo t\u00e9rmino, porque en \u00a0la \u00a0etapa \u00a0instructiva \u00a0no obra constancia de que la Fiscal\u00eda hubiese procurado \u00a0notificar \u00a0las \u00a0decisiones \u00a0proferidas a quienes figuraban como defensores de su \u00a0cliente, \u00a0todo lo cual pone de presente el cuadro de desamparo e indefensi\u00f3n en \u00a0que el procesado debi\u00f3 enfrentar el proceso seguido en su contra. \u00a0\u00a0<\/p>\n<p>As\u00ed, en la indagatoria rendida el 28 de mayo \u00a0de \u00a01993, \u00a0la \u00a0Fiscal\u00eda \u00a0design\u00f3 como defensora a una estudiante de derecho de \u00a0quien \u00a0ni \u00a0siquiera \u00a0se \u00a0dej\u00f3 constancia de su nombre, y el procesado tan s\u00f3lo \u00a0hizo \u00a0manifestaciones \u00a0referentes \u00a0a sus datos personales, pues guard\u00f3 silencio \u00a0frente \u00a0 a \u00a0los \u00a0hechos \u00a0por \u00a0carecer \u00a0de \u00a0abogado \u00a0titulado \u00a0que \u00a0lo \u00a0asistiera \u00a0procesalmente, \u00a0ante \u00a0lo \u00a0cual se dio por terminada la diligencia, cuando lo que \u00a0ha \u00a0debido \u00a0hacer es acudir al servicio de defensor\u00eda p\u00fablica o designar a uno \u00a0de \u00a0 los \u00a0 tantos \u00a0 abogados \u00a0 titulados \u00a0 que \u00a0 ejercen \u00a0 en \u00a0 la \u00a0 ciudad \u00a0 de \u00a0Pereira. \u00a0\u00a0<\/p>\n<p>Posteriormente, \u00a0se \u00a0practic\u00f3 diligencia de \u00a0ampliaci\u00f3n \u00a0de \u00a0indagatoria \u00a0con asistencia del abogado Conrado Osorno Moncada, \u00a0quien \u00a0asumi\u00f3 el cargo s\u00f3lo para dicha actuaci\u00f3n y como tal no\u00a0 llev\u00f3 a \u00a0cabo \u00a0ninguna \u00a0gesti\u00f3n \u00a0en pro de su asistido, pues no existe constancia de que \u00a0hubiere \u00a0solicitado \u00a0pruebas, interpuesto recursos o se notificara personalmente \u00a0de \u00a0decisiones \u00a0importantes \u00a0como \u00a0aquella \u00a0mediante \u00a0la \u00a0cual \u00a0se \u00a0defini\u00f3 \u00a0la \u00a0situaci\u00f3n \u00a0jur\u00eddica, \u00a0el \u00a0cierre \u00a0de \u00a0la investigaci\u00f3n o la calificaci\u00f3n del \u00a0sumario, \u00a0y \u00a0la Fiscal\u00eda tambi\u00e9n omiti\u00f3 comunicarle tales decisiones, sin que \u00a0tampoco \u00a0obre \u00a0constancia \u00a0de \u00a0que \u00a0se hubiese notificado mediante anotaci\u00f3n en \u00a0estado. \u00a0\u00a0<\/p>\n<p>La \u00a0diligencia \u00a0de reconocimiento en fila de \u00a0personas \u00a0fue aplazada por raz\u00f3n de no haber comparecido el defensor de CABRERA \u00a0G\u00d3MEZ, \u00a0sin \u00a0que en el proceso obre constancia que permita aclarar el motivo de \u00a0su \u00a0ausencia, \u00a0y \u00a0en \u00a0la \u00a0llevada \u00a0a \u00a0cabo \u00a0posteriormente, fue asistido por una \u00a0estudiante \u00a0de \u00a0derecho \u00a0quien al parecer fue nombrada de oficio y s\u00f3lo para la \u00a0realizaci\u00f3n de dicha prueba.\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>El \u00a0tres \u00a0de \u00a0septiembre \u00a0de mil novecientos \u00a0noventa \u00a0y \u00a0tres se declar\u00f3 cerrada la investigaci\u00f3n, mediante pronunciamiento \u00a0que \u00a0se notific\u00f3 personalmente al procesado pero sin que aparezca constancia de \u00a0su \u00a0 notificaci\u00f3n \u00a0 al \u00a0 defensor \u00a0 quien \u00a0adem\u00e1s \u00a0no \u00a0present\u00f3 \u00a0alegatos \u00a0de \u00a0conclusi\u00f3n, \u00a0en \u00a0vista \u00a0de \u00a0lo \u00a0cual \u00a0el \u00a0sindicado \u00a0asumi\u00f3 \u00a0su propia defensa \u00a0solicitando \u00a0la \u00a0cesaci\u00f3n de procedimiento lo que indica que estuvo desprovisto \u00a0de \u00a0defensa t\u00e9cnica, como de igual manera se pone en evidencia con el posterior \u00a0memorial \u00a0presentado donde solicita el traslado a una c\u00e1rcel de Medell\u00edn a fin \u00a0de \u00a0poder \u00a0contar \u00a0con \u00a0una \u00a0mejor \u00a0defensa, \u00a0lo \u00a0que \u00a0fue \u00a0ignorado por el ente \u00a0acusador. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s \u00a0de \u00a0lo \u00a0anterior, la violaci\u00f3n del \u00a0derecho \u00a0de \u00a0defensa resulta palmaria al punto que el procesado ni siquiera tuvo \u00a0acceso \u00a0al \u00a0expediente ya que el 31 de agosto de 1993 solicit\u00f3 se le expidieran \u00a0copias \u00a0y \u00a0ello \u00a0fue \u00a0denegado \u00a0mediante auto del 24 de septiembre siguiente. En \u00a0\u00faltimas, \u00a0 la \u00a0Fiscal\u00eda \u00a0no \u00a0vel\u00f3 \u00a0por \u00a0el \u00a0cumplimiento \u00a0de \u00a0las \u00a0garant\u00edas \u00a0constitucionales \u00a0del procesado en cuanto no le design\u00f3 a un defensor de oficio \u00a0ni \u00a0acudi\u00f3 \u00a0a \u00a0la defensor\u00eda p\u00fablica para que asumiera la defensa t\u00e9cnica en \u00a0la forma como lo ordenan la Constituci\u00f3n y la ley. \u00a0\u00a0<\/p>\n<p>Esta \u00a0ausencia de defensa t\u00e9cnica continu\u00f3 \u00a0durante \u00a0el \u00a0juicio \u00a0en \u00a0el cual \u201csigue haci\u00e9ndose notar como gran ausente la \u00a0defensa \u00a0t\u00e9cnica: \u00a0Ni \u00a0una \u00a0sola \u00a0notificaci\u00f3n, \u00a0ni \u00a0un solo memorial, ning\u00fan \u00a0alegato, \u00a0ninguna \u00a0solicitud \u00a0de \u00a0pruebas como actividades defensivas realizadas \u00a0por \u00a0un \u00a0profesional \u00a0del \u00a0derecho en favor del imputado\u201d. S\u00f3lo hasta el 5 de \u00a0octubre \u00a0de \u00a01994, \u00a0el \u00a0procesado \u00a0design\u00f3 a un profesional del derecho a\u00a0 \u00a0quien \u00a0el \u00a024 \u00a0siguiente \u00a0se \u00a0le \u00a0reconoci\u00f3 personer\u00eda, y que tampoco realiz\u00f3 \u00a0ninguna actuaci\u00f3n defensiva a favor de CABRERA G\u00d3MEZ. \u00a0\u00a0<\/p>\n<p>El \u00a09 \u00a0de \u00a0diciembre \u00a0el procesado confiri\u00f3 \u00a0poder \u00a0a otro profesional del derecho quien vino a asumir la defensa t\u00e9cnica en \u00a0momentos \u00a0en \u00a0que \u00a0el \u00a0juicio \u00a0estaba \u00a0ad portas de concluir con la sentencia de \u00a0primera instancia. \u00a0\u00a0<\/p>\n<p>Considera \u00a0 entonces \u00a0 que \u00a0no \u00a0por \u00a0haber \u00a0participado \u00a0en \u00a0el \u00a0proceso \u00a0varios \u00a0defensores, algunos de ellos no titulados, \u00a0puede \u00a0afirmarse que se garantiz\u00f3 el derecho de defensa t\u00e9cnica del procesado. \u00a0Por \u00a0el \u00a0contrario, \u00a0result\u00f3 \u00a0gravemente \u00a0vulnerado \u00a0pues \u00a0aflora \u00a0la \u00a0falta de \u00a0asistencia \u00a0y \u00a0asesor\u00eda \u00a0de \u00a0un \u00a0abogado que presentara alegaciones, solicitara \u00a0pruebas \u00a0de \u00a0descargo, \u00a0controvirtiera \u00a0las \u00a0de \u00a0cargo, impugnara las decisiones \u00a0adversas, \u00a0solicitara \u00a0las nulidades que advirtiera, o por lo menos orientara al \u00a0procesado \u00a0sobre las diversas estrategias defensivas y posibilidades legales que \u00a0pod\u00eda \u00a0adoptar para hacer menos gravosa su situaci\u00f3n, como rebajas de pena por \u00a0sometimiento \u00a0a la justicia o\u00a0 beneficios por colaboraci\u00f3n eficaz, ninguna \u00a0de las cuales estuvo al alcance de MIGUEL ANTONIO CABRERA G\u00d3MEZ. \u00a0\u00a0<\/p>\n<p>Con fundamento en lo expuesto solicita de la \u00a0Corte \u00a0casar \u00a0la \u00a0sentencia \u00a0y \u00a0anular \u00a0lo \u00a0actuado a partir de la diligencia de \u00a0indagatoria \u00a0del \u00a0procesado \u00a0a \u00a0fin \u00a0de \u00a0que \u00a0se \u00a0reponga \u00a0la \u00a0actuaci\u00f3n y sean \u00a0observadas \u00a0 las \u00a0 garant\u00edas \u00a0 fundamentales \u00a0 del \u00a0 enjuiciado \u00a0 (fls. \u00a0186 \u00a0y \u00a0ss.). \u00a0\u00a0<\/p>\n<p>3.- \u00a0A nombre del \u00a0procesado URIEL MONROY. \u00a0\u00a0<\/p>\n<p>UNICO CARGO. (Violaci\u00f3n indirecta de normas \u00a0de derecho \u00a0sustancial).\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Con \u00a0fundamento \u00a0en \u00a0la \u00a0causal \u00a0primera \u00a0de \u00a0casaci\u00f3n, \u00a0cuerpo \u00a0segundo, \u00a0el actor denuncia que la sentencia del Tribunal es \u00a0indirectamente \u00a0violatoria \u00a0de \u00a0disposiciones \u00a0de \u00a0derecho \u00a0sustancial por haber \u00a0incurrido \u00a0en \u00a0errores \u00a0de \u00a0derecho \u00a0en \u00a0la \u00a0apreciaci\u00f3n \u00a0probatoria, en cuanto \u00a0admiti\u00f3 \u00a0y confiri\u00f3 valor a un medio irregularmente aportado al proceso ya que \u00a0se omitieron las formalidades para su aducci\u00f3n. \u00a0\u00a0<\/p>\n<p>Indica que en la diligencia de ampliaci\u00f3n de \u00a0indagatoria \u00a0del \u00a0procesado \u00a0MIGUEL \u00a0ANTONIO \u00a0CABRERA, \u00a0debi\u00f3 \u00a0ser juramentado, \u00a0exhortado \u00a0a \u00a0decir \u00a0la \u00a0verdad \u00a0y conminado con las penas que le acarrear\u00eda el \u00a0falso \u00a0testimonio, en relaci\u00f3n con los cargos que formul\u00f3 en contra de MONROY, \u00a0no \u00a0obstante lo cual se omiti\u00f3 el cumplimiento de los requisitos procesales que \u00a0son \u00a0de \u00a0rigor \u00a0en \u00a0estos eventos, previstos por el art\u00edculo 285 del C\u00f3digo de \u00a0procedimiento penal de 1991. \u00a0\u00a0<\/p>\n<p>\u201cComo \u00a0las sindicaciones de CABRERA contra \u00a0MONROY \u00a0no fueron objeto de alguna controversia y se admitieron como ciertas sin \u00a0verificarlas, \u00a0dejaron \u00a0expedito \u00a0el \u00a0camino \u00a0para \u00a0que, \u00a0circunstancias \u00a0apenas \u00a0indiciarias \u00a0como \u00a0la presencia del sindicado en las vecindades de Telecom, o su \u00a0mentira, \u00a0 \u00a0hubieran \u00a0 sido \u00a0 consideradas \u00a0 como \u00a0 pruebas \u00a0 incontrovertibles, \u00a0coadyuvantes \u00a0a \u00a0la \u00a0sentencia \u00a0recurrida. \u00a0El \u00a0fallador \u00a0debi\u00f3 inferir que las \u00a0acusaciones \u00a0formuladas \u00a0por \u00a0coacusados, \u00a0sin la presencia de otras pruebas que \u00a0les \u00a0den credibilidad, responden, en la mayor\u00eda de los casos, a sentimientos de \u00a0venganza, \u00a0a malicia o a la esperanza de sacar ventajas personales y son, por lo \u00a0tanto, frecuentemente m\u00e1s mentira que verdad\u201d. \u00a0\u00a0<\/p>\n<p>En \u00a0 \u00a0este \u00a0 evento, \u00a0 MONROY \u00a0 explic\u00f3 \u00a0suficientemente \u00a0las \u00a0razones \u00a0de \u00a0su \u00a0presencia en el lugar de su captura, pues \u00a0hab\u00eda \u00a0transportado \u00a0hasta \u00a0all\u00ed \u00a0a \u00a0MIRTHA \u00a0P\u00c9REZ, su suegra, atendiendo una \u00a0solicitud \u00a0 de \u00a0 ella \u00a0 a \u00a0la \u00a0que \u00a0dif\u00edcilmente \u00a0pod\u00eda \u00a0negarse \u00a0por \u00a0ser \u00a0su \u00a0hu\u00e9sped. \u00a0\u00a0<\/p>\n<p>Luego de citar algunos doctrinantes, refiere \u00a0que \u00a0la sentencia impugnada indica que MONROY manifest\u00f3 no conocer a CABRERA no \u00a0obstante \u00a0conocerlo \u00a0desde \u00a0ocho \u00a0a\u00f1os \u00a0atr\u00e1s, de lo cual dedujo el indicio de \u00a0mentira, \u00a0y \u00a0junto con el de presencia sirvieron de respaldo para fundamentar la \u00a0condena. \u00a0\u201c \u00a0De nuevo es preciso repetir lo ya expresado, haber conferido a la \u00a0indagatoria \u00a0valor \u00a0probatorio \u00a0condujo a concederle car\u00e1cter de plena prueba a \u00a0dos \u00a0 circunstancias \u00a0 que, \u00a0 consideradas \u00a0 individualmente, \u00a0 eran \u00a0 solamente \u00a0indiciarias\u201d. \u00a0\u00a0<\/p>\n<p>Sin \u00a0embargo, \u00a0MONROY en la indagatoria dijo \u00a0conocer \u00a0a \u00a0EDGAR \u00a0ARIAS \u00a0OROZCO, \u00a0lo \u00a0que demuestra su absoluta inocencia, pues \u00a0\u201cadmite \u00a0que \u00a0lo \u00a0conoce \u00a0porque \u00a0ignoraba \u00a0sus \u00a0il\u00edcitas \u00a0actividades, y las \u00a0ignoraba precisamente porque era ajeno a ellas\u201d. \u00a0\u00a0<\/p>\n<p>No acontece igual cuando es interrogado sobre \u00a0su \u00a0conocimiento \u00a0de CABRERA, que niega de plano, pues teme verse involucrado en \u00a0el \u00a0problema \u00a0de \u00a0aqu\u00e9l \u00a0que \u00a0fue \u00a0capturado en situaci\u00f3n de flagrancia cuando \u00a0realizaba \u00a0las llamadas extorsivas. \u201cBien se conoce en los estrados judiciales \u00a0la \u00a0frecuencia \u00a0con \u00a0que, \u00a0a\u00fan los acusados inocentes, echan mano de la mentira \u00a0dentro \u00a0de \u00a0la \u00a0exposici\u00f3n \u00a0de la verdad, con la esperanza de salvarse, sin que \u00a0este artificio pruebe nada en orden a su culpabilidad\u201d. \u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0la \u00a0sentencia se dict\u00f3 confiri\u00e9ndole \u00a0valor \u00a0probatorio \u00a0a \u00a0un medio irregularmente incorporado a la actuaci\u00f3n. \u201cSe \u00a0excluy\u00f3 \u00a0toda duda razonable y el fallador se aferr\u00f3 de tal modo a la versi\u00f3n \u00a0de \u00a0CABRERA, \u00a0que \u00a0ni \u00a0siquiera \u00a0quiso \u00a0tener \u00a0en \u00a0consideraci\u00f3n la posibilidad \u00a0contraria\u201d. \u00a0\u00a0<\/p>\n<p>Concluye \u00a0entonces \u00a0considerando \u00a0que existe \u00a0ilegalidad \u00a0de \u00a0la indagatoria de MIGUEL ANTONIO CABRERA en la que se formularon \u00a0cargos \u00a0contra \u00a0MONROY con omisi\u00f3n de las formalidades que la ley exige para su \u00a0aducci\u00f3n, \u00a0a \u00a0pesar \u00a0de lo cual los juzgadores admitieron y confirieron m\u00e9rito \u00a0persuasivo. \u00a0\u00a0<\/p>\n<p>Afirma \u00a0que hubo error en la apreciaci\u00f3n de \u00a0los \u00a0cargos \u00a0ya que el fallo condenatorio requiere de la presencia de dos o m\u00e1s \u00a0indicios \u00a0 graves \u00a0 y \u00a0 en \u00a0 este \u00a0 evento \u00a0 obra \u00a0 s\u00f3lo \u00a0uno \u00a0y \u00a0leve, \u00a0el \u00a0de \u00a0mentira. \u00a0\u00a0<\/p>\n<p>El \u00a0 fallo \u00a0se \u00a0dict\u00f3 \u00a0sobre \u00a0acusaciones \u00a0formuladas \u00a0por \u00a0CABRERA \u00a0que \u00a0no \u00a0fueron \u00a0objeto \u00a0de \u00a0comprobaci\u00f3n, pues no se \u00a0demostr\u00f3 \u00a0la \u00a0necesaria \u00a0vinculaci\u00f3n \u00a0causal \u00a0de MONROY con los hechos por los \u00a0cuales \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 le \u00a0sentenci\u00f3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Como \u00a0normas \u00a0sustanciales \u00a0transgredidas, \u00a0indica \u00a0el \u00a0art\u00edculo \u00a0primero de la ley 40 de 1993, \u201cpor darle aplicaci\u00f3n en \u00a0perjuicio \u00a0de \u00a0URIEL \u00a0MONROY \u00a0cuando \u00a0no \u00a0lo era conforme a las pruebas\u201d, cuya \u00a0transgresi\u00f3n \u00a0\u201csurge de error en la apreciaci\u00f3n del caudal probatorio, y, el \u00a0art\u00edculo \u00a02, \u00a0porque \u00a0la \u00a0conducta \u00a0no \u00a0se \u00a0demostr\u00f3 \u00a0t\u00edpica, antijur\u00eddica y \u00a0culpable\u201d. \u00a0\u00a0<\/p>\n<p>Con fundamento en lo anterior solicita de la \u00a0Corte \u00a0casar \u00a0parcialmente \u00a0la \u00a0sentencia impugnada en cuanto al procesado URIEL \u00a0MONROY (fls. 231 y ss.). \u00a0\u00a0<\/p>\n<p>\u00a0 Concepto del \u00a0Agente del Ministerio P\u00fablico.-\u00a0 \u00a0\u00a0<\/p>\n<p>El \u00a0Procurador segundo delegado en lo penal, \u00a0frente \u00a0a \u00a0las demandas presentadas y los cargos contenidos en ellas, concept\u00faa \u00a0de la manera siguiente: \u00a0\u00a0<\/p>\n<p>1.- \u00a0A nombre del \u00a0procesado EDGAR ARIAS OROZCO. \u00a0\u00a0<\/p>\n<p>Comienza \u00a0por advertir que la censura que el \u00a0demandante \u00a0postula \u00a0carece de idoneidad para desvirtuar la doble presunci\u00f3n de \u00a0acierto \u00a0y \u00a0legalidad \u00a0que ampara las sentencias de segunda instancia, en cuanto \u00a0se sale de todo rigor t\u00e9cnico orientado a dicho prop\u00f3sito. \u00a0\u00a0<\/p>\n<p>Observa\u00a0 \u00a0al \u00a0efecto \u00a0que el demandante \u00a0enuncia \u00a0el \u00a0reproche \u00a0como \u00a0violaci\u00f3n \u00a0directa \u00a0de \u00a0la \u00a0ley pero el desarrollo \u00a0corresponde \u00a0a la v\u00eda indirecta en cuanto se dedica a cuestionar la valoraci\u00f3n \u00a0probatoria, \u00a0pero \u00a0de \u00a0forma \u00a0incompleta \u00a0y confusa en la medida en que deja los \u00a0ataques \u00a0en \u00a0simples \u00a0enunciados \u00a0e \u00a0involucra \u00a0dentro \u00a0de \u00a0un solo cargo falsos \u00a0juicios \u00a0de identidad, falsos juicios de legalidad y nulidades, reproches que ha \u00a0debido formular y demostrar en cargos aut\u00f3nomos. \u00a0\u00a0<\/p>\n<p>Destaca \u00a0que cuando se acude a la violaci\u00f3n \u00a0directa \u00a0de \u00a0la \u00a0ley \u00a0sustancial \u00a0por \u00a0v\u00eda \u00a0directa, \u00a0se \u00a0da por sentado que el \u00a0demandante \u00a0acepta los hechos declarados en el fallo y, en consecuencia, que los \u00a0medios \u00a0probatorios \u00a0fueron debidamente valorados,\u00a0 ubicando el yerro en la \u00a0selecci\u00f3n \u00a0o \u00a0interpretaci\u00f3n \u00a0de \u00a0la \u00a0norma, \u00a0es \u00a0decir, limitar el discurso a \u00a0razones \u00a0 \u00a0exclusivamente \u00a0 \u00a0de \u00a0 \u00a0derecho \u00a0 \u00a0para \u00a0 demostrar \u00a0 la \u00a0 pretendida \u00a0violaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Como el libelista equivoca la modalidad de la \u00a0violaci\u00f3n, \u00a0el \u00a0cargo \u00a0aparece \u00a0indebidamente \u00a0formulado, \u00a0lo \u00a0que conduce a su \u00a0fracaso. \u00a0\u00a0<\/p>\n<p>No \u00a0obstante, agrega que los reproches a los \u00a0medios \u00a0probatorios, \u00a0los \u00a0cuales \u00a0corresponden \u00a0a \u00a0la \u00a0modalidad \u00a0indirecta \u00a0de \u00a0violaci\u00f3n \u00a0de la ley sustancial, tambi\u00e9n presentan fallas t\u00e9cnicas, en cuanto \u00a0se \u00a0quedan \u00a0en \u00a0enunciados \u00a0incompletos, \u00a0pues no precisa el actor, a trav\u00e9s de \u00a0qu\u00e9 \u00a0tipo de error, de hecho o de derecho en sus diferentes manifestaciones, se \u00a0produce \u00a0la \u00a0pretendida \u00a0violaci\u00f3n, \u00a0y \u00a0tampoco \u00a0logra \u00a0demostrar ning\u00fan yerro \u00a0trascendente \u00a0 \u00a0que \u00a0 \u00a0afecte \u00a0 \u00a0la \u00a0 estructura \u00a0 l\u00f3gica \u00a0 de \u00a0 la \u00a0 decisi\u00f3n \u00a0impugnada. \u00a0\u00a0<\/p>\n<p>El \u00a0recurrente plantea el desconocimiento de \u00a0la \u00a0presunci\u00f3n \u00a0de \u00a0inocencia \u00a0y \u00a0el \u00a0consecuente \u00a0fen\u00f3meno \u00a0de \u00a0la duda, pero \u00a0acude\u00a0 \u00a0a \u00a0t\u00e9rminos \u00a0muy \u00a0gaseosos que no logran demostrar cu\u00e1les son las \u00a0hip\u00f3tesis \u00a0que \u00a0se \u00a0omitieron \u00a0en punto de la exclusi\u00f3n de responsabilidad del \u00a0procesado \u00a0para \u00a0poder predicar la falta de certeza o vulneraci\u00f3n del principio \u00a0in dubio pro reo. \u00a0\u00a0<\/p>\n<p>Si \u00a0bien \u00a0es \u00a0cierto \u00a0que el censor aduce la \u00a0configuraci\u00f3n \u00a0de \u00a0falso \u00a0juicio \u00a0de \u00a0identidad, no lo desarrolla ni demuestra, \u00a0pues \u00a0en lugar de determinar los medios de convicci\u00f3n sobre los cuales recae el \u00a0yerro, \u00a0 y \u00a0acreditar \u00a0que \u00a0su \u00a0contenido \u00a0fue \u00a0tergiversado \u00a0por \u00a0el \u00a0fallador, \u00a0manifiesta \u00a0 tan \u00a0s\u00f3lo \u00a0que \u00a0las \u00a0declaraciones \u00a0de \u00a0las \u00a0coprocesadas \u00a0no \u00a0son \u00a0imparciales \u00a0y que las hip\u00f3tesis que sustentan los indicios no fueron probadas, \u00a0lo \u00a0que \u00a0de ninguna manera es suficiente para desquiciar la sentencia materia de \u00a0impugnaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Igual \u00a0acontece respecto de la alegaci\u00f3n en \u00a0el \u00a0sentido \u00a0de que las pruebas allegadas no re\u00fanen los requisitos establecidos \u00a0para \u00a0su \u00a0aducci\u00f3n, \u00a0o \u00a0que se les atribuy\u00f3 un m\u00e9rito que no les corresponde, \u00a0pues \u00a0a \u00a0la \u00a0falta \u00a0de \u00a0desarrollo \u00a0de \u00a0los falsos juicios de legalidad y falsos \u00a0juicios \u00a0de \u00a0convicci\u00f3n, \u00a0se \u00a0agrega \u00a0que \u00a0no \u00a0toma \u00a0en cuenta que en el actual \u00a0sistema \u00a0probatorio \u00a0estos \u00a0\u00faltimos \u00a0no \u00a0tienen \u00a0cabida \u00a0debido a que la ley no \u00a0predetermina \u00a0el \u00a0valor \u00a0de las pruebas sino que su apreciaci\u00f3n se hace bajo el \u00a0sistema de apreciaci\u00f3n racional o sana cr\u00edtica. \u00a0\u00a0<\/p>\n<p>En \u00a0 la \u00a0 demanda \u00a0 tambi\u00e9n \u00a0se \u00a0plantean \u00a0irregularidades \u00a0que de llegar a demostrarse dar\u00edan lugar a la invalidaci\u00f3n de \u00a0la \u00a0 actuaci\u00f3n \u00a0 procesal, \u00a0 entre \u00a0otras \u00a0por \u00a0no \u00a0seguirse \u00a0el \u00a0principio \u00a0de \u00a0investigaci\u00f3n \u00a0integral, las cuales debieron desarrollarse en cargos diferentes \u00a0por ser de naturaleza distinta a la de la causal primera. \u00a0\u00a0<\/p>\n<p>Finalmente, el actor termina desnaturalizando \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n, \u00a0pues \u00a0a \u00a0manera \u00a0de alegato de instancia muestra su \u00a0apreciaci\u00f3n \u00a0 personal \u00a0 de \u00a0 los \u00a0 medios \u00a0 de \u00a0 prueba \u00a0 que \u00a0 obran \u00a0 en \u00a0el \u00a0expediente. \u00a0\u00a0<\/p>\n<p>Lo anterior lleva a la Delegada a considerar \u00a0que el cargo debe desestimarse. \u00a0\u00a0<\/p>\n<p>2.- \u00a0A nombre del \u00a0procesado MIGUEL ANTONIO CABRERA G\u00d3MEZ. \u00a0\u00a0<\/p>\n<p>Luego \u00a0de \u00a0hacer \u00a0algunas \u00a0consideraciones \u00a0generales \u00a0en torno al derecho de defensa como garant\u00eda constitucional y una de \u00a0las \u00a0manifestaciones \u00a0del debido proceso, destaca que la defensa, comprendida en \u00a0sus \u00a0dos \u00a0modalidades \u00a0t\u00e9cnica y material, debe estar garantizada por el Estado \u00a0desde \u00a0el \u00a0inicio \u00a0de \u00a0la \u00a0actuaci\u00f3n hasta la finalizaci\u00f3n del juzgamiento, de \u00a0manera \u00a0que \u00a0el \u00a0funcionario \u00a0judicial \u00a0tiene \u00a0la \u00a0obligaci\u00f3n \u00a0de \u00a0velar por su \u00a0ejercicio \u00a0real, \u00a0pues \u00a0de \u00a0no \u00a0ser as\u00ed, el ordenamiento ha previsto la nulidad \u00a0como \u00a0mecanismo \u00a0para \u00a0amparar \u00a0a \u00a0los \u00a0sujetos \u00a0procesales\u00a0 \u00a0frente \u00a0a \u00a0su \u00a0vulneraci\u00f3n. \u00a0\u00a0<\/p>\n<p>Respecto \u00a0de la defensa t\u00e9cnica, manifiesta \u00a0que \u00a0la \u00a0doctrina \u00a0y \u00a0la \u00a0jurisprudencia \u00a0un\u00e1nimemente \u00a0han \u00a0sostenido que debe \u00a0traspasar \u00a0las \u00a0fronteras \u00a0de \u00a0la \u00a0formalidad, \u00a0para \u00a0llegar a ser real\u00a0 en \u00a0despliegue \u00a0 de \u00a0 actividades \u00a0 defensivas, \u00a0 eficaces \u00a0y \u00a0consecuentes \u00a0en \u00a0las \u00a0circunstancias \u00a0en \u00a0que \u00a0se \u00a0encuentre \u00a0el sindicado en cada caso, sin que quepa \u00a0predicar \u00a0su \u00a0efectivo \u00a0ejercicio \u00a0por el simple nombramiento de un abogado como \u00a0defensor, sino de su eficaz participaci\u00f3n. \u00a0\u00a0<\/p>\n<p>En este caso, si bien MIGUEL ANTONIO CABRERA \u00a0G\u00d3MEZ \u00a0cont\u00f3 \u00a0formalmente \u00a0con \u00a0un \u00a0defensor \u00a0durante la etapa de instrucci\u00f3n \u00a0designado \u00a0en \u00a0la indagatoria realizada el 3 de junio de 1993, \u00e9ste no cumpli\u00f3 \u00a0con \u00a0su \u00a0cometido \u00a0en tanto que la \u00fanica actuaci\u00f3n que llev\u00f3 a cabo fue la de \u00a0asistencia \u00a0a dicha diligencia pues ni siquiera se present\u00f3 para notificarse de \u00a0resoluciones \u00a0tan \u00a0importantes \u00a0como la de situaci\u00f3n jur\u00eddica, el cierre de la \u00a0investigaci\u00f3n \u00a0o \u00a0la \u00a0calificaci\u00f3n \u00a0del \u00a0m\u00e9rito \u00a0del \u00a0sumario, lo que para la \u00a0Delegada \u00a0no denota otra cosa que abandono de la actividad defensiva, la cual ni \u00a0siquiera \u00a0estuvo \u00a0presente \u00a0en \u00a0el \u00a0plano \u00a0de \u00a0la posibilidad, pues el sindicado \u00a0Cabrera \u00a0lleg\u00f3 a carecer hasta del consejo m\u00e1s elemental a fin de adelantar la \u00a0defensa \u00a0material que es lo m\u00ednimo que puede exig\u00edrsele a un abogado defensor, \u00a0raz\u00f3n \u00a0por \u00a0la \u00a0cual \u00a0resulta viable predicar que la garant\u00eda de la defensa se \u00a0vio \u00a0quebrantada durante la etapa de instrucci\u00f3n y en el per\u00edodo probatorio de \u00a0la causa, como lo apunta el casacionista. \u00a0\u00a0<\/p>\n<p>A \u00a0la circunstancia de que Cabrera G\u00f3mez no \u00a0cont\u00f3 \u00a0durante \u00a0la \u00a0etapa \u00a0sumarial \u00a0con \u00a0asesor\u00eda \u00a0jur\u00eddica \u00a0adecuada por la \u00a0negligencia \u00a0del \u00a0abogado \u00a0que \u00a0actuaba \u00a0como \u00a0defensor, \u00a0debe \u00a0agregarse que la \u00a0Fiscal\u00eda \u00a0coadyuv\u00f3 \u00a0a \u00a0la \u00a0vulneraci\u00f3n \u00a0del derecho a la defensa por no haber \u00a0agotado \u00a0los \u00a0medios legales para que tuviera una efectiva defensa t\u00e9cnica como \u00a0acudir \u00a0a \u00a0la \u00a0defensor\u00eda p\u00fablica o designarle un defensor de oficio como bien \u00a0lo \u00a0hace \u00a0notar \u00a0el \u00a0demandante, \u00a0y porque al no autorizar la expedici\u00f3n de las \u00a0copias \u00a0solicitadas \u00a0por \u00a0el \u00a0encartado tambi\u00e9n obstaculiz\u00f3 el ejercicio de la \u00a0defensa material. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0anterior, \u00a0considera \u00a0que \u00a0se \u00a0debe \u00a0acceder \u00a0a las pretensiones del casacionsita, por cuanto el derecho a la defensa \u00a0de \u00a0Miguel \u00a0Antonio \u00a0Cabrera \u00a0G\u00f3mez \u00a0se \u00a0ha \u00a0visto \u00a0conculcado \u00a0en \u00a0el proceso, \u00a0principalmente \u00a0en \u00a0la \u00a0etapa \u00a0de \u00a0la \u00a0investigaci\u00f3n. Sugiere, en consecuencia, \u00a0declarar \u00a0la \u00a0nulidad \u00a0del \u00a0proceso en relaci\u00f3n con este sindicado a partir del \u00a0cierre \u00a0de la investigaci\u00f3n, a fin de que se le brinden todas las garant\u00edas de \u00a0defensa t\u00e9cnica y material. \u00a0\u00a0<\/p>\n<p>3.- A nombre del \u00a0procesado URIEL MONROY. \u00a0\u00a0<\/p>\n<p>Advierte \u00a0la \u00a0Delegada \u00a0que \u00a0el \u00a0censor \u00a0no \u00a0demuestra \u00a0c\u00f3mo \u00a0se llegar\u00eda a la indebida aplicaci\u00f3n del art\u00edculo 1\u00ba de la \u00a0ley \u00a040 de 1993, pues la \u00fanica norma procedimental que cita es el art\u00edculo 285 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0procedimiento \u00a0penal de 1991 que se refiere a las formalidades \u00a0previas \u00a0 a \u00a0la \u00a0recepci\u00f3n \u00a0del \u00a0testimonio \u00a0cuando \u00a0la \u00a0actuaci\u00f3n \u00a0que \u00a0est\u00e1 \u00a0cuestionando \u00a0es \u00a0la \u00a0indagatoria \u00a0de \u00a0Miguel \u00a0Antonio \u00a0Cabrera, \u00a0por \u00a0lo que la \u00a0disposici\u00f3n \u00a0a \u00a0la \u00a0que \u00a0debi\u00f3 referirse era la que regula esta diligencia, en \u00a0concreto el art\u00edculo 357 ejusdem. \u00a0\u00a0<\/p>\n<p>A \u00a0pesar de no hab\u00e9rsele tomado juramento a \u00a0Cabrera \u00a0G\u00f3mez \u00a0cuando \u00a0afirm\u00f3 \u00a0que \u00a0Monroy \u00a0era el encargado de distribuir el \u00a0dinero \u00a0para \u00a0los \u00a0vi\u00e1ticos, \u00a0y \u00a0que cuidaba del menor secuestrado, la Delegada \u00a0considera \u00a0que \u00a0la indagatoria no sufre mengua en su legalidad y en consecuencia \u00a0en \u00a0su \u00a0capacidad \u00a0probatoria, \u00a0debido \u00a0a que tiene la doble connotaci\u00f3n de ser \u00a0medio \u00a0de \u00a0defensa y a su vez de medio probatorio sin que se observe que se haya \u00a0omitido \u00a0ninguna \u00a0formalidad \u00a0sustancial \u00a0para \u00a0su \u00a0recepci\u00f3n \u00a0y \u00a0aducci\u00f3n \u00a0al \u00a0proceso. \u00a0\u00a0<\/p>\n<p>Si \u00a0bien \u00a0es \u00a0cierto \u00a0no \u00a0se hizo caso de la \u00a0previsi\u00f3n \u00a0consagrada \u00a0en \u00a0el art\u00edculo 357 del Estatuto procesal por el que se \u00a0rigi\u00f3 \u00a0el \u00a0asunto, \u00a0esta \u00a0circunstancia \u00a0no \u00a0le \u00a0resta \u00a0valor \u00a0probatorio \u00a0a la \u00a0indagatoria \u00a0debido a que este formalismo ha sido instituido para no dejar en la \u00a0impunidad \u00a0un \u00a0eventual falso testimonio, conforme as\u00ed ha sido declarado por la \u00a0jurisprudencia. \u00a0\u00a0<\/p>\n<p>De \u00a0 esta \u00a0manera \u00a0cabe \u00a0concluir \u00a0que \u00a0la \u00a0afirmaci\u00f3n \u00a0del \u00a0libelista \u00a0de \u00a0que \u00a0la \u00a0indagatoria \u00a0se aport\u00f3 al proceso con \u00a0omisi\u00f3n \u00a0de \u00a0formalidades, no es cierta, y en consecuencia queda desdibujada la \u00a0repercusi\u00f3n \u00a0que \u00a0le \u00a0atribuye el actor a la falta de juramento con relaci\u00f3n a \u00a0lo narrado sobre Uriel Monroy. \u00a0\u00a0<\/p>\n<p>A \u00a0m\u00e1s \u00a0de lo anterior, el demandante no se \u00a0aviene \u00a0a \u00a0la \u00a0t\u00e9cnica \u00a0casacional \u00a0pues \u00a0al \u00a0tratar de darle credibilidad a su \u00a0tesis, \u00a0se dedica a analizar el dicho de su defendido para concluir que es ajeno \u00a0a \u00a0las \u00a0conductas \u00a0delictivas \u00a0que se le imputan, lo cual resulta v\u00e1lido en las \u00a0instancias pero impertinente en sede extraordinaria. \u00a0\u00a0<\/p>\n<p>De \u00a0 aceptarse \u00a0la \u00a0existencia \u00a0del \u00a0yerro \u00a0probatorio \u00a0planteado, al demandante le compet\u00eda desvirtuar la totalidad de los \u00a0fundamentos \u00a0que \u00a0sustentan \u00a0la \u00a0sentencia, \u00a0en \u00a0este \u00a0caso las versiones de los \u00a0dem\u00e1s \u00a0coprocesados, \u00a0el reconocimiento de la v\u00edctima del secuestro, y toda la \u00a0estructura \u00a0 indiciaria, \u00a0 aspectos \u00a0 que \u00a0 sin \u00a0 embargo \u00a0 no \u00a0son \u00a0materia \u00a0de \u00a0controversia. \u00a0\u00a0<\/p>\n<p>Acorde con lo anterior, la Delegada sugiere a \u00a0la \u00a0Corte \u00a0desestimar \u00a0las \u00a0demandas \u00a0presentas a nombre de Edgar Arias Orozco y \u00a0Uriel \u00a0Monroy, \u00a0y \u00a0declarar \u00a0la \u00a0nulidad \u00a0parcial de lo actuado en relaci\u00f3n con \u00a0Miguel \u00a0Antonio \u00a0Cabrera \u00a0G\u00f3mez, \u00a0a \u00a0partir \u00a0de \u00a0la resoluci\u00f3n de cierre de la \u00a0investigaci\u00f3n, \u00a0por encontrar que el derecho a la defensa se vio afectado en la \u00a0etapa de instrucci\u00f3n (fls. 6 y ss. cno. Corte).\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 \u00a0<\/p>\n<p>SE \u00a0 \u00a0 \u00a0 \u00a0CONSIDERA:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>La \u00a0Corte \u00a0aprehender\u00e1 \u00a0el \u00a0estudio \u00a0de las \u00a0censuras \u00a0planteadas \u00a0en \u00a0las demandas, en el mismo orden observado para efectos \u00a0de su resumen. \u00a0\u00a0<\/p>\n<p>1.- \u00a0A nombre del \u00a0procesado EDGAR ARIAS OROZCO. \u00a0\u00a0<\/p>\n<p>UNICO CARGO. (Violaci\u00f3n directa de normas de \u00a0derecho sustancial). \u00a0\u00a0<\/p>\n<p>Desde \u00a0el \u00a0enunciado \u00a0mismo \u00a0del \u00a0cargo \u00a0se \u00a0advierte \u00a0total desapego a la t\u00e9cnica casacional lo que inexorablemente conduce \u00a0a \u00a0su \u00a0desestimaci\u00f3n \u00a0por \u00a0la Corte. No obstante acudir el demandante a la v\u00eda \u00a0directa, \u00a0no \u00a0s\u00f3lo \u00a0omite \u00a0precisar \u00a0el \u00a0sentido \u00a0de la violaci\u00f3n en cuanto se \u00a0desconoce \u00a0cu\u00e1les \u00a0disposiciones \u00a0de \u00a0derecho \u00a0sustancial \u00a0fueron indebidamente \u00a0aplicadas, \u00a0cu\u00e1les \u00a0otras \u00a0fueron \u00a0dejadas \u00a0de \u00a0aplicar \u00a0o \u00a0cu\u00e1les \u00a0resultaron \u00a0err\u00f3neamente \u00a0interpretadas, \u00a0sino que adem\u00e1s, indebida y contradictoriamente, \u00a0en \u00a0su \u00a0desarrollo \u00a0incursiona \u00a0en \u00a0el \u00e1mbito de la transgresi\u00f3n indirecta que \u00a0tampoco culmina. \u00a0\u00a0<\/p>\n<p>Es \u00a0as\u00ed \u00a0como \u00a0dejando \u00a0de lado el deber de \u00a0aceptar \u00a0los \u00a0hechos \u00a0y \u00a0la \u00a0ponderaci\u00f3n \u00a0de las pruebas\u00a0 realizada por el \u00a0juzgador, \u00a0y \u00a0omitir \u00a0la \u00a0obligaci\u00f3n \u00a0de \u00a0presentar \u00a0el disenso en el plano del \u00a0estricto \u00a0raciocinio \u00a0jur\u00eddico \u00a0como \u00a0corresponde \u00a0cuando \u00a0se \u00a0acude \u00a0a la v\u00eda \u00a0directa, \u00a0el \u00a0casacionista pretende fundamentar el reproche con el argumento que \u00a0al \u00a0procesado EDGAR ARIAS OROZCO se le conden\u00f3 \u00fanica y exclusivamente con base \u00a0en \u00a0lo \u00a0declarado \u00a0por \u00a0MIRTHA \u00a0P\u00c9REZ PULECIO, STELLA CULLMAN JIM\u00c9NEZ y JANETH \u00a0SUSANA \u00a0JIM\u00c9NEZ \u00a0V\u00c1SQUEZ, \u00a0cuyas \u00a0declaraciones \u00a0califica \u00a0de contradictorias, \u00a0carentes \u00a0de \u00a0objetividad, \u00a0imparcialidad\u00a0 \u00a0y m\u00e9rito persuasivo, por haber \u00a0sido \u00a0rendidas \u00a0\u201ccon el fin de vengarse del pobre ciudadano ajeno por completo \u00a0a los hechos punibles\u201d. \u00a0\u00a0<\/p>\n<p>Queda \u00a0as\u00ed en evidencia que la intenci\u00f3n y \u00a0finalidad \u00a0de \u00a0la censura no es denunciar transgresi\u00f3n directa de disposiciones \u00a0de \u00a0derecho sustancial, sino controvertir los hechos declarados en el fallo y la \u00a0ponderaci\u00f3n \u00a0de \u00a0la \u00a0prueba \u00a0realizada \u00a0por \u00a0el \u00a0juzgador, en cuyo evento se ha \u00a0debido \u00a0acudir a la v\u00eda indirecta y postular un concreto tipo de error de hecho \u00a0o de derecho en la apreciaci\u00f3n de los medios. \u00a0\u00a0<\/p>\n<p>No \u00a0obstante, \u00a0a\u00fan \u00a0de \u00a0suponerse \u00a0que \u00a0la \u00a0pretensi\u00f3n \u00a0 es \u00a0 demostrar \u00a0 la \u00a0configuraci\u00f3n \u00a0de \u00a0errores \u00a0de \u00a0apreciaci\u00f3n \u00a0probatoria, \u00a0dando \u00a0al traste con sus aspiraciones desquiciatorias del fallo, el \u00a0actor \u00a0tampoco \u00a0precisa \u00a0si \u00a0el \u00a0yerro \u00a0cometido fue falso juicio de existencia, \u00a0falso \u00a0juicio \u00a0de identidad o falso raciocinio como manifestaciones del error de \u00a0hecho, \u00a0o \u00a0falso juicio de legalidad o de convicci\u00f3n como expresiones del error \u00a0de \u00a0derecho, \u00a0al \u00a0punto \u00a0que \u00a0respecto de los mismos medios ataca por igual y de \u00a0manera \u00a0contradictoria\u00a0 \u00a0las \u00a0condiciones en que se produjo su aducci\u00f3n al \u00a0proceso, \u00a0la tergiversaci\u00f3n por el juzgador, y el m\u00e9rito persuasivo conferido, \u00a0lo \u00a0cual \u00a0convierte \u00a0su \u00a0escrito \u00a0en \u00a0una mezcla ininteligible de propuestas sin \u00a0ilaci\u00f3n ni concreci\u00f3n ninguna. \u00a0\u00a0<\/p>\n<p>Al \u00a0efecto \u00a0es \u00a0de observarse, que cuando el \u00a0libelista \u00a0afirma \u00a0que \u00a0\u201clas \u00a0pruebas \u00a0recaudadas \u00a0no \u00a0re\u00fanen \u00a0los requisitos \u00a0exigidos \u00a0por \u00a0el \u00a0precepto que establece su ritual ceremonial\u201d era de suponer \u00a0que \u00a0enunciara \u00a0y \u00a0desarrollara un cargo concreto fundado en la existencia de un \u00a0error \u00a0de \u00a0derecho \u00a0por \u00a0falso \u00a0juicio de legalidad al haber sido apreciados los \u00a0medios \u00a0no obstante haberse recaudado con transgresi\u00f3n de las normas que reglan \u00a0su producci\u00f3n o aducci\u00f3n al proceso. \u00a0\u00a0<\/p>\n<p>Del mismo modo, al afirmar que a las citadas \u00a0pruebas \u00a0\u201cse \u00a0le ha atribuido un valor legal que no merecen y por lo tanto que \u00a0no \u00a0le \u00a0corresponden\u201d, \u00a0era de su cargo fundar la censura en la configuraci\u00f3n \u00a0de \u00a0 errores \u00a0 de \u00a0 derecho \u00a0por \u00a0falso \u00a0juicio \u00a0de \u00a0convicci\u00f3n \u00a0indicando \u00a0las \u00a0disposiciones \u00a0procesales \u00a0que \u00a0prefijan \u00a0su \u00a0m\u00e9rito \u00a0o eficacia y demostrar al \u00a0tiempo \u00a0que los juzgadores les confirieron uno diverso, lo cual por su puesto no \u00a0se \u00a0aviene al principio de que en materia penal, por lo general, no tiene cabida \u00a0la tarifa legal para estimaci\u00f3n de la prueba.\u00a0 \u00a0\u00a0<\/p>\n<p>Igualmente, cuando el demandante aduce \u201cque \u00a0a \u00a0la \u00a0prueba \u00a0legalmente \u00a0recaudada \u00a0se le ha impreso, impartido un sentimiento \u00a0f\u00e1ctico \u00a0diverso \u00a0del \u00a0que \u00a0naturalmente \u00a0le \u00a0corresponde\u201d, \u00a0ten\u00eda por carga \u00a0indicar \u00a0a \u00a0cu\u00e1les \u00a0medios \u00a0se refiere, qu\u00e9 concretamente dicen ellos, de qu\u00e9 \u00a0manera \u00a0el \u00a0juzgador \u00a0los \u00a0tergivers\u00f3, \u00a0cercen\u00f3 \u00a0o \u00a0adicion\u00f3 en su expresi\u00f3n \u00a0f\u00e1ctica \u00a0para \u00a0hacerles \u00a0producir \u00a0efectos \u00a0que no se establecen de su contexto \u00a0objetivo, \u00a0y \u00a0c\u00f3mo \u00a0de no haberse cometido el desacierto, las declaraciones del \u00a0fallo \u00a0habr\u00edan \u00a0conducido \u00a0a una soluci\u00f3n sustancialmente distinta y opuesta a \u00a0la \u00a0 contenida \u00a0 en \u00a0 su \u00a0 parte \u00a0 resolutiva, \u00a0 nada \u00a0 de \u00a0 lo \u00a0 cual \u00a0siquiera \u00a0intenta. \u00a0\u00a0<\/p>\n<p>Y \u00a0cuando \u00a0ataca las inferencias indiciarias \u00a0realizadas \u00a0por \u00a0el \u00a0juzgador, \u00a0por \u00a0parte alguna de su discurso el casacionista \u00a0precisa \u00a0a \u00a0cu\u00e1les \u00a0indicios \u00a0se \u00a0est\u00e1 \u00a0refiriendo, \u00a0ni \u00a0cual fue el postulado \u00a0l\u00f3gico \u00a0o \u00a0regla \u00a0de \u00a0experiencia \u00a0que en cada caso resultaron desconocidos. Se \u00a0limita \u00a0tan \u00a0s\u00f3lo \u00a0a \u00a0aducir que \u201cno se utilizaron las reglas y las leyes del \u00a0buen \u00a0pensar, que son aquellas que prescriben la disciplina de la l\u00f3gica, de la \u00a0realidad\u201d. \u00a0\u00a0<\/p>\n<p>A \u00a0 \u00a0este \u00a0 \u00a0c\u00famulo \u00a0 de \u00a0 desaciertos, \u00a0contradictoriamente \u00a0el demandante agrega otro no menos trascendente relacionado \u00a0con \u00a0la \u00a0presunta \u00a0transgresi\u00f3n al principio de investigaci\u00f3n integral, evento \u00a0en \u00a0el \u00a0cual \u00a0ha \u00a0debido \u00a0acudir \u00a0en cap\u00edtulo separado a la causal tercera para \u00a0denunciar \u00a0que \u00a0el \u00a0fallo fue proferido en juicio viciado de nulidad,\u00a0 y no \u00a0postular \u00a0la \u00a0denuncia \u00a0al \u00a0amparo de la causal primera que supone la validez de \u00a0\u00e9ste. \u00a0\u00a0<\/p>\n<p>Como quiera, entonces, que la demanda ostenta \u00a0insalvables \u00a0defectos \u00a0t\u00e9cnicos \u00a0y \u00a0de \u00a0fundamentaci\u00f3n \u00a0que impiden a la Corte \u00a0proveer \u00a0un \u00a0pronunciamiento \u00a0de \u00a0fondo \u00a0a \u00a0las manifestaciones de inconformidad \u00a0contenidas \u00a0en \u00a0ella, \u00a0por \u00a0prohibirlo \u00a0el \u00a0principio de limitaci\u00f3n que rige su \u00a0actuaci\u00f3n, \u00a0en \u00a0total \u00a0acuerdo \u00a0con la Delegada no cabe m\u00e1s alternativa que su \u00a0desestimaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>2.- \u00a0A nombre del \u00a0procesado \u00a0 \u00a0 \u00a0 \u00a0 MIGUEL \u00a0 \u00a0 \u00a0 \u00a0ANTONIO \u00a0 \u00a0 \u00a0 \u00a0CABRERA \u00a0 \u00a0 \u00a0 \u00a0G\u00d3MEZ.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Contrario \u00a0a \u00a0lo que acontece con la demanda \u00a0que \u00a0precede, \u00a0la \u00a0Corte \u00a0advierte \u00a0que \u00a0la \u00a0propuesta \u00a0de ataque consistente en \u00a0violaci\u00f3n \u00a0del \u00a0derecho de defensa, por ausencia de asistencia profesional, que \u00a0este \u00a0cargo \u00a0contiene, \u00a0cumple \u00a0los \u00a0requerimientos t\u00e9cnicos necesarios para su \u00a0estudio, \u00a0pues \u00a0el \u00a0casacionista \u00a0es \u00a0claro \u00a0en \u00a0precisar la causal de casaci\u00f3n \u00a0invocada \u00a0(tercera), \u00a0el \u00a0motivo de nulidad (violaci\u00f3n del derecho de defensa), \u00a0las \u00a0razones \u00a0que \u00a0le sirven de fundamento (ausencia de defensa t\u00e9cnica), y las \u00a0normas \u00a0violadas \u00a0(art\u00edculo 29 de la Carta Pol\u00edtica\u00a0 y 304 del C\u00f3digo de \u00a0Procedimiento Penal de 1991). \u00a0\u00a0<\/p>\n<p>Se proceder\u00e1, entonces, al estudio de fondo, \u00a0anticipando, \u00a0desde \u00a0ya, que el casacionista tiene raz\u00f3n cuando sostiene que el \u00a0procesado \u00a0CABRERA \u00a0G\u00d3MEZ \u00a0careci\u00f3 de asistencia t\u00e9cnica durante toda la fase \u00a0de \u00a0la \u00a0investigaci\u00f3n y parte del juicio, por abandono del proceso de quien fue \u00a0designado \u00a0en \u00a0la \u00a0diligencia \u00a0de \u00a0indagatoria para cumplir dicho encargo, y que \u00a0esta \u00a0informalidad \u00a0estructura \u00a0la \u00a0causal de nulidad prevista en el numeral 3\u00ba \u00a0del \u00a0art\u00edculo 304 del C\u00f3digo de Procedimiento Penal de 1991 (hoy art. 306-3 de \u00a0la \u00a0ley \u00a0600 \u00a0de \u00a02000), \u00a0en \u00a0cuanto \u00a0atenta \u00a0contra \u00a0el \u00a0derecho que tiene todo \u00a0sindicado \u00a0 a \u00a0la \u00a0asistencia \u00a0de \u00a0un \u00a0abogado \u00a0durante \u00a0la \u00a0instrucci\u00f3n \u00a0y \u00a0el \u00a0juzgamiento, \u00a0consagrado \u00a0en \u00a0los art\u00edculos 29 de la Carta Pol\u00edtica, y 1\u00ba del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0de \u00a01991 \u00a0(art. \u00a08\u00ba \u00a0del \u00a0Nuevo \u00a0C\u00f3digo \u00a0de \u00a0procedimiento penal).\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>La \u00a0Corte \u00a0ha \u00a0sido \u00a0reiterativa en se\u00f1alar \u00a0que\u00a0 \u00a0la \u00a0defensa \u00a0t\u00e9cnica \u00a0es \u00a0una \u00a0prerrogativa \u00a0intangible, \u00a0y \u00a0que \u00a0su \u00a0ejercicio \u00a0debe \u00a0ser permanente y real. Intangible, en cuanto que el imputado no \u00a0puede \u00a0renunciar a ella, ni el Estado a su obligaci\u00f3n de garantizarlo. Si quien \u00a0es \u00a0vinculado \u00a0al \u00a0proceso \u00a0no \u00a0quiere \u00a0o no est\u00e1 en condiciones de designar un \u00a0abogado \u00a0que \u00a0lo asista en el tr\u00e1mite, el \u00f3rgano judicial tiene la obligaci\u00f3n \u00a0de \u00a0prove\u00e9rselo, \u00a0y \u00a0de \u00a0estar \u00a0atento \u00a0a \u00a0su \u00a0desempe\u00f1o, asegur\u00e1ndose que su \u00a0gesti\u00f3n \u00a0se \u00a0cumpla \u00a0dentro \u00a0de \u00a0los marcos de la diligencia debida y la \u00e9tica \u00a0profesional. \u00a0\u00a0<\/p>\n<p>Permanente, porque por mandato constitucional \u00a0(art\u00edculo \u00a029) \u00a0debe \u00a0ser garantizado durante todo el proceso (investigaci\u00f3n y \u00a0juzgamiento), \u00a0sin \u00a0ninguna \u00a0clase \u00a0de \u00a0limitaciones, y porque siendo condici\u00f3n \u00a0esencial \u00a0de validez de la actuaci\u00f3n, no puede estar referido a solo un estadio \u00a0de \u00a0ella, \u00a0ni \u00a0convertirse \u00a0en \u00a0una \u00a0prerrogativa \u00a0opcional \u00a0en \u00a0el tr\u00e1mite del \u00a0proceso, \u00a0ni \u00a0hacerse \u00a0depender \u00a0de las posibilidades de \u00e9xito de su ejercicio, \u00a0atendida \u00a0la \u00a0mayor \u00a0o \u00a0menor \u00a0contundencia \u00a0de \u00a0la prueba incriminatoria.\u00a0 \u00a0\u00a0<\/p>\n<p>Real, \u00a0en \u00a0cuanto \u00a0que \u00a0su ejercicio no pude \u00a0entenderse \u00a0garantizado \u00a0por \u00a0la \u00a0sola \u00a0circunstancia \u00a0de contar nominalmente el \u00a0imputado \u00a0con \u00a0un \u00a0abogado \u00a0defensor durante la investigaci\u00f3n y el juzgamiento, \u00a0sino \u00a0que es necesario que se realice materialmente, mediante actos positivos de \u00a0gesti\u00f3n, \u00a0o de actitudes vigilantes del acontecer procesal, susceptibles de ser \u00a0constatadas \u00a0a trav\u00e9s de actuaciones objetivas\u00a0 ( Cfr. casaciones de 22 de \u00a0septiembre \u00a0de 1998, 22 de octubre de 1999 y 7 de septiembre de 2000, Magistrado \u00a0Ponente \u00a0Arboleda \u00a0Ripoll; \u00a02 de mayo de 2001 , rad. 13387 M.P. C\u00f3rdoba Poveda; \u00a024 \u00a0de \u00a0julio de 2001, rad. 11578, M.P. G\u00e1lvez Argote; 13 de diciembre de 2001, \u00a0rad. \u00a011207, M.P. G\u00f3mez Gallego; y 18 de enero de 2002, rad. 14109, M.P. P\u00e9rez \u00a0Pinz\u00f3n; entre otras). \u00a0\u00a0<\/p>\n<p>Sobre la inactividad profesional como motivo \u00a0de \u00a0ineficacia \u00a0de \u00a0la \u00a0actuaci\u00f3n \u00a0procesal, \u00a0la \u00a0Corte \u00a0ha \u00a0sido insistente en \u00a0se\u00f1alar \u00a0que \u00a0el \u00a0defensor, \u00a0en cumplimiento de su funci\u00f3n, puede optar por el \u00a0silencio \u00a0como \u00a0estrategia defensiva, pero que esta forma de valorar su gesti\u00f3n \u00a0debe \u00a0aparecer \u00a0corroborada \u00a0por actos procesales que acrediten cuando menos una \u00a0m\u00ednima \u00a0actividad \u00a0vigilante de su parte, puesto que de lo contrario habr\u00eda de \u00a0afirmarse \u00a0abandono \u00a0del \u00a0compromiso adquirido, y por tanto, ausencia de defensa \u00a0t\u00e9cnica, \u00a0cuyos \u00a0efectos \u00a0invalidatorios \u00a0depender\u00e1n \u00a0de \u00a0la \u00a0constataci\u00f3n de \u00a0haberse \u00a0quebrantado \u00a0realmente el derecho de contar con una defensa cualificada \u00a0y oportuna. \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 \u00a0<\/p>\n<p>Revisada \u00a0la \u00a0actuaci\u00f3n \u00a0procesal \u00a0en \u00a0el \u00a0presente \u00a0caso, \u00a0se establece que MIGUEL ANTONIO CABRERA G\u00d3MEZ fue escuchado en \u00a0indagatoria \u00a0por \u00a0la \u00a0Fiscal\u00eda el 3 de junio de 1993 en la ciudad de Pereira, y \u00a0que \u00a0en \u00a0esta diligencia design\u00f3 al doctor Conrado Osorno Moncada con domicilio \u00a0profesional \u00a0en \u00a0esa \u00a0ciudad \u00a0como \u00a0su \u00a0defensor \u00a0de confianza, quien limit\u00f3 su \u00a0actuaci\u00f3n \u00a0a \u00a0la \u00a0intervenci\u00f3n en dicho acto procesal (fls. 153 y ss. cno. 1). \u00a0Desde \u00a0entonces, \u00a0hasta \u00a0el \u00a05 de octubre de 1994, cuando fue reemplazado por el \u00a0doctor \u00a0Hernando \u00a0Jim\u00e9nez \u00a0Gonz\u00e1lez \u00a0(fls. 134 y 136 cno. 2), habiendo sido ya \u00a0superada \u00a0la \u00a0fase \u00a0instructiva \u00a0y \u00a0calificado el m\u00e9rito probatorio del sumario \u00a0(fls. \u00a0293 \u00a0-1 \u00a0y \u00a0362 \u00a0y ss. -1), no aparece actuaci\u00f3n suya de \u00edndole alguna, \u00a0indicativa \u00a0de \u00a0que \u00a0hubiese \u00a0realizado actos positivos de gesti\u00f3n, o estuviera \u00a0atento al devenir procesal. \u00a0\u00a0<\/p>\n<p>M\u00e1s \u00a0a\u00fan. \u00a0En \u00a0el \u00a0expediente \u00a0no aparecen \u00a0constancias \u00a0 que \u00a0 durante \u00a0la \u00a0instrucci\u00f3n \u00a0se \u00a0hubieren \u00a0librado \u00a0oficios \u00a0o \u00a0comunicaciones \u00a0 a \u00a0la \u00a0direcci\u00f3n \u00a0registrada \u00a0por \u00a0el \u00a0doctor \u00a0Conrado \u00a0Osorno \u00a0Moncada\u00a0 \u00a0con \u00a0el \u00a0fin de notificarlo de las resoluciones de definici\u00f3n de \u00a0la \u00a0situaci\u00f3n \u00a0jur\u00eddica, \u00a0clausura \u00a0de \u00a0la \u00a0investigaci\u00f3n y calificaci\u00f3n del \u00a0sumario, \u00a0o \u00a0que \u00a0se haya notificado de dichas determinaciones, como tampoco que \u00a0hiciera \u00a0presencia \u00a0en \u00a0el \u00a0recaudo \u00a0probatorio, o procedido a solicitar copias, \u00a0pedir \u00a0 pr\u00e1ctica \u00a0 de \u00a0 pruebas \u00a0o \u00a0interponer \u00a0alg\u00fan \u00a0recurso, \u00a0sin \u00a0que \u00a0los \u00a0funcionarios \u00a0de instrucci\u00f3n o de juzgamiento se percataran de la irregularidad \u00a0que \u00a0 ven\u00eda \u00a0 present\u00e1ndose, \u00a0 pues \u00a0 durante \u00a0 el \u00a0juicio, \u00a0a \u00a0pesar \u00a0de \u00a0las \u00a0comunicaciones libradas, nunca compareci\u00f3 al proceso. \u00a0\u00a0<\/p>\n<p>Esta relaci\u00f3n de sucesos f\u00e1ctico procesales \u00a0reafirma \u00a0lo \u00a0dicho \u00a0en \u00a0precedencia, \u00a0en el sentido de que el abogado designado \u00a0para \u00a0atender \u00a0la \u00a0defensa \u00a0del \u00a0sindicado, \u00a0abandon\u00f3 \u00a0el asunto despu\u00e9s de la \u00a0indagatoria, \u00a0y \u00a0que \u00a0desde \u00a0entonces, \u00a0hasta \u00a0bien \u00a0avanzado \u00a0el \u00a0juicio cuando \u00a0design\u00f3 \u00a0un \u00a0abogado \u00a0de confianza MIGUEL ANTONIO CABRERA G\u00d3MEZ\u00a0 careci\u00f3 \u00a0de \u00a0asistencia \u00a0t\u00e9cnica, sin que los funcionarios de instrucci\u00f3n y juzgamiento \u00a0adoptaran \u00a0 medidas \u00a0 encaminadas \u00a0a \u00a0corregir \u00a0la \u00a0irregularidad, \u00a0en \u00a0aras \u00a0de \u00a0garantizar \u00a0la \u00a0adecuada \u00a0integraci\u00f3n del contradictorio, y el aseguramiento de \u00a0las \u00a0debidas \u00a0condiciones \u00a0de equilibrio para que el indagado pudiera enfrentar, \u00a0en \u00a0t\u00e9rminos \u00a0de igualdad, el ente acusador, como correspond\u00eda hacerlo, acorde \u00a0con \u00a0 lo \u00a0establecido \u00a0en \u00a0el \u00a0art\u00edculo \u00a0147 \u00a0inciso \u00a0segundo \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0de \u00a01991 \u00a0(hoy \u00a0art. \u00a0136 \u00a0de \u00a0la \u00a0ley 600 de 2000).\u00a0 \u00a0\u00a0<\/p>\n<p>Esto \u00a0por \u00a0cuanto siendo la defensa funci\u00f3n \u00a0p\u00fablica, \u00a0es \u00a0entendido \u00a0que \u00a0dicho \u00a0control \u00a0debe \u00a0proyectarse sobre cualquier \u00a0categor\u00eda \u00a0de \u00a0apoderados \u00a0(de oficio, contractuales, p\u00fablicos), con el fin de \u00a0asegurar \u00a0una \u00a0asistencia \u00a0profesional \u00a0proba, \u00a0y \u00a0evitar \u00a0que \u00a0la validez de la \u00a0actuaci\u00f3n \u00a0pueda \u00a0verse \u00a0afectada \u00a0de nulidad por ausencia de defensa t\u00e9cnica, \u00a0derivada \u00a0 de \u00a0 la \u00a0 gesti\u00f3n \u00a0 que \u00a0 social \u00a0 y \u00a0 jur\u00eddicamente \u00a0les \u00a0ha \u00a0sido \u00a0encomendada. \u00a0\u00a0<\/p>\n<p>Dicha situaci\u00f3n de desamparo determin\u00f3 que \u00a0la \u00a0fase \u00a0de \u00a0la \u00a0investigaci\u00f3n \u00a0fuese \u00a0adelantada \u00a0de manera unilateral por la \u00a0Fiscal\u00eda, \u00a0y \u00a0que el procesado no pudiera ejercer en debida forma el derecho de \u00a0contradicci\u00f3n \u00a0durante \u00a0este importante estadio del proceso, a trav\u00e9s de actos \u00a0positivos \u00a0de \u00a0controversia \u00a0probatoria, impugnaci\u00f3n o alegaci\u00f3n, orientados a \u00a0controvertir \u00a0la \u00a0prueba \u00a0allegada en su contra, o hacia la verificaci\u00f3n de las \u00a0explicaciones suministradas en su injurada. \u00a0\u00a0<\/p>\n<p>Estas \u00a0 \u00a0consideraciones \u00a0 no \u00a0 resultan \u00a0demeritadas, \u00a0ni \u00a0siquiera \u00a0por el hecho de que durante la instrucci\u00f3n, ante la \u00a0no \u00a0comparecencia \u00a0del defensor de confianza (fl. 253-1), se hubiere designado a \u00a0una \u00a0abogada \u00a0con \u00a0licencia temporal que asistiera al procesado en la diligencia \u00a0de \u00a0reconocimiento \u00a0en \u00a0fila \u00a0de personas (fls. 255 y ss. cno. 1), pues es claro \u00a0que \u00a0a \u00a0m\u00e1s \u00a0de \u00a0dicha \u00a0actuaci\u00f3n \u00a0ninguna \u00a0otra \u00a0llev\u00f3 \u00a0a cabo en pro de los \u00a0intereses del procesado. \u00a0\u00a0<\/p>\n<p>Podr\u00eda \u00a0pensarse, \u00a0sin \u00a0embargo, \u00a0que \u00a0por \u00a0haberse \u00a0negado \u00a0el \u00a0procesado \u00a0a \u00a0rendir \u00a0indagatoria \u00a0sin \u00a0la asistencia de un \u00a0defensor \u00a0de confianza (fl. 88-1), denota que se trata de una persona conocedora \u00a0de \u00a0sus \u00a0derechos \u00a0y avezado en este tipo de procesos,\u00a0 por lo mismo que el \u00a0silencio de su abogado constituy\u00f3 una estrategia defensiva. \u00a0\u00a0<\/p>\n<p>No \u00a0obstante, \u00a0es de advertir, de una parte, \u00a0que \u00a0por \u00a0virtud \u00a0de \u00a0lo \u00a0dispuesto \u00a0por \u00a0el \u00a0art\u00edculo \u00a0308-4 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0procedimiento \u00a0penal por el que se rigi\u00f3 el asunto (art. 310-3 de la ley 600 de \u00a02000), \u00a0la \u00a0falta \u00a0de \u00a0defensa t\u00e9cnica como irregularidad sustancial que genera \u00a0nulidad \u00a0no resulta convalidada por la actitud del procesado que con su conducta \u00a0la \u00a0haya \u00a0coadyuvado, \u00a0y, \u00a0de \u00a0otra, \u00a0que en la actuaci\u00f3n obran constancias que \u00a0ponen \u00a0en \u00a0evidencia \u00a0la \u00a0ausencia \u00a0absoluta \u00a0de \u00a0vigilancia \u00a0del proceso por el \u00a0defensor. \u00a0\u00a0<\/p>\n<p>N\u00f3tese \u00a0al \u00a0efecto \u00a0que \u00a0el \u00a0procesado \u00a0fue \u00a0capturado \u00a0en \u00a0Ibagu\u00e9 (fl. 147-1), recluido en la C\u00e1rcel de varones de Pereira \u00a0donde \u00a0permaneci\u00f3 durante toda la fase de instrucci\u00f3n y gran parte del juicio, \u00a0hasta \u00a0el \u00a024 \u00a0de \u00a0octubre \u00a0de \u00a01995 \u00a0(fl. \u00a0477-2) \u00a0cuando fue trasladado por la \u00a0Direcci\u00f3n \u00a0del Inpec a la C\u00e1rcel del Distrito judicial de Medell\u00edn, ciudad en \u00a0la \u00a0cual \u00a0se llev\u00f3 a cabo la investigaci\u00f3n y el juzgamiento.\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 \u00a0<\/p>\n<p>En dichas condiciones el procesado asumi\u00f3 su \u00a0propia \u00a0defensa, pues ni siquiera pod\u00eda tener acceso al expediente no s\u00f3lo por \u00a0tramitarse \u00a0en \u00a0una ciudad distinta de aquella donde se encontraba privado de la \u00a0libertad \u00a0sino \u00a0por que adem\u00e1s solicit\u00f3 copias de la actuaci\u00f3n \u201ctendiente a \u00a0plantear \u00a0 mi \u00a0 defensa\u201d \u00a0(fl. \u00a0308-1), \u00a0las \u00a0que \u00a0le \u00a0fueron \u00a0negadas \u00a0\u201cpor \u00a0prohibici\u00f3n \u00a0del \u00a0art\u00edculo 37 del Decreto 2790 de 1990\u201d, seg\u00fan se indica en \u00a0la \u00a0resoluci\u00f3n expedida por el Fiscal regional de Medell\u00edn el 24 de septiembre \u00a0de \u00a01993 (fl. 315-1), lo cual si bien no constituye irregularidad acorde con los \u00a0instrumentos \u00a0normativos \u00a0que \u00a0por \u00a0entonces prohib\u00edan la expedici\u00f3n de copias \u00a0durante \u00a0la \u00a0fase \u00a0de \u00a0instrucci\u00f3n, \u00a0de \u00a0todos \u00a0modos \u00a0denota que el proceso se \u00a0adelant\u00f3 a sus espaldas. \u00a0\u00a0<\/p>\n<p>En \u00a0tales \u00a0circunstancias\u00a0 \u00a0present\u00f3 \u00a0alegatos \u00a0de \u00a0conclusi\u00f3n (fl. 332), y m\u00e1s tarde solicit\u00f3 al Fiscal instructor \u00a0se \u00a0autorizara su traslado a una c\u00e1rcel de la ciudad de Medell\u00edn, argumentando \u00a0al \u00a0efecto \u00a0\u201cuna \u00a0mejor defensa\u201d, ya que \u201cpor encontrarse mi proceso en la \u00a0ciudad \u00a0de \u00a0Medell\u00edn, se me facilitar\u00e1 contar con el apoyo de un abogado amigo \u00a0que \u00a0estar\u00eda \u00a0a \u00a0disposici\u00f3n \u00a0para ayudarme en mi defensa y as\u00ed poder aportar \u00a0con \u00a0la mayor prontitud las pruebas que dar\u00edan luz definitivamente a mi favor y \u00a0poder \u00a0colaborar \u00a0con \u00a0ustedes para lograr recuperar ya mi anhelada libertad\u201d, \u00a0agregando \u00a0adem\u00e1s \u00a0razones de \u201ctipo econ\u00f3mico\u201d, pues, \u201csi no he colocado \u00a0un \u00a0abogado \u00a0para \u00a0mi defensa, es porque no tuve dinero para tal efecto\u201d (fls. \u00a0346). \u00a0\u00a0<\/p>\n<p>Ello \u00a0patentiza, \u00a0que \u00a0el \u00a0procesado puso de \u00a0presente \u00a0al \u00a0Fiscal \u00a0instructor el abandono a que ven\u00eda siendo sometido por el \u00a0defensor \u00a0que \u00a0lo \u00a0asisti\u00f3 \u00a0en \u00a0la \u00a0indagatoria, \u00a0y sin embargo no fue o\u00eddo de \u00a0manera \u00a0que \u00a0el \u00a0vicio \u00a0de \u00a0garant\u00eda \u00a0que \u00a0ahora se denuncia por el demandante, \u00a0pudiera \u00a0verse \u00a0oportunamente \u00a0corregido, \u00a0pues \u00a0por \u00a0toda \u00a0respuesta \u00a0obtuvo la \u00a0contenida \u00a0en \u00a0el \u00a0numeral \u00a0sexto de la providencia calificatoria, en el sentido \u00a0de\u00a0 \u00a0ordenar \u00a0\u201cpor \u00a0secretar\u00eda, \u00a0oficiar \u00a0a \u00a0la \u00a0Direcci\u00f3n \u00a0General \u00a0de \u00a0Prisiones, \u00a0a fin de que se estudie la posibilidad de trasladar a MIGUEL ANTONIO \u00a0CABRERA \u00a0G\u00d3MEZ \u00a0desde \u00a0la \u00a0ciudad \u00a0de Pereira a\u00a0 la c\u00e1rcel de Bellavista, \u00a0seg\u00fan \u00a0argumentos \u00a0del \u00a0folio \u00a0345\u201d \u00a0(fl. \u00a0389), \u00a0sin \u00a0que obre constancia de \u00a0haberse \u00a0librado \u00a0el \u00a0citado \u00a0oficio, \u00a0sino \u00a0s\u00f3lo la justificaci\u00f3n que corre a \u00a0folio 451. \u00a0\u00a0<\/p>\n<p>Lo expuesto resulta corroborado con el oficio \u00a0fechado \u00a0el \u00a027 \u00a0de \u00a0octubre \u00a0de \u00a01993, \u00a0dirigido \u00a0a \u00a0la \u00a0Direcci\u00f3n Regional de \u00a0Fiscal\u00edas \u00a0de Medell\u00edn por el Procurador Judicial 152 con sede en Pereira (fl. \u00a0393-1) \u00a0 con \u00a0 posterioridad \u00a0 a \u00a0 la \u00a0 calificaci\u00f3n \u00a0del \u00a0sumario \u00a0en \u00a0primera \u00a0instancia,\u00a0 \u00a0donde \u00a0manifiesta \u00a0que \u00a0\u201cEl \u00a0se\u00f1or \u00a0Miguel \u00a0Antonio Cabrera \u00a0G\u00f3mez \u00a0est\u00e1 \u00a0detenido \u00a0en \u00a0la \u00a0c\u00e1rcel de esta ciudad desde el mes de mayo del \u00a0presente \u00a0 a\u00f1o \u00a0 sindicado \u00a0de \u00a0la \u00a0comisi\u00f3n \u00a0del \u00a0delito \u00a0de \u00a0extorsi\u00f3n. \u00a0La \u00a0instrucci\u00f3n \u00a0del \u00a0sumario \u00a0cursa \u00a0en \u00a0la \u00a0fiscal\u00eda regional de Medell\u00edn\u201d, y \u00a0agrega: \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u201cAl \u00a0visitar la \u00a0c\u00e1rcel, \u00a0el \u00a0citado \u00a0recluso \u00a0se \u00a0quej\u00f3 \u00a0porque, \u00a0seg\u00fan \u00a0\u00e9l, tiene a toda su \u00a0familia \u00a0y \u00a0amigos en Medell\u00edn, gente toda que le podr\u00eda ayudar, por lo menos, \u00a0a \u00a0conseguir \u00a0un \u00a0abogado \u00a0y \u00a0solicit\u00f3 \u00a0su \u00a0remisi\u00f3n \u00a0para \u00a0esa ciudad y no ha \u00a0recibido \u00a0ninguna respuesta. Por lo anterior, le ruego \u00a0de \u00a0la \u00a0manera \u00a0m\u00e1s encarecida, ordenar a los funcionarios bajo su mando que le \u00a0den \u00a0tr\u00e1mite \u00a0a la solicitud y el recluso sepa a qu\u00e9 atenerse\u201d (se destaca). \u00a0Esta petici\u00f3n fue reiterada el 25 de abril de 1994 (fl. 490-1). \u00a0\u00a0<\/p>\n<p>A m\u00e1s de lo anterior, el procesado solicit\u00f3 \u00a0se \u00a0le \u00a0expidieran \u00a0copias de la actuaci\u00f3n (fl. 454), las cuales si bien fueron \u00a0autorizadas \u00a0por \u00a0prove\u00eddo de treinta y uno de enero de mil novecientos noventa \u00a0y \u00a0cuatro \u00a0de \u00a0conformidad \u00a0con lo dispuesto por el art\u00edculo 20 de la ley 81 de \u00a01993 \u00a0(fl. \u00a0452), \u00a0y \u00a0se \u00a0libr\u00f3 comunicaci\u00f3n inform\u00e1ndole sobre el particular \u00a0(fl. \u00a0475), \u00a0lo \u00a0cierto \u00a0es \u00a0que \u00a0no fueron expedidas, pues no de otra manera se \u00a0explica \u00a0de \u00a0una \u00a0parte, \u00a0el oficio del 25 de mayo de 1994\u00a0 suscrito por el \u00a0Procurador \u00a0Judicial \u00a0152 \u00a0de \u00a0Pereira \u00a0en el sentido de que \u201cel se\u00f1or MANUEL \u00a0ANTONIO \u00a0CABRERA \u00a0G\u00d3MEZ \u00a0est\u00e1 por cuenta de los funcionarios de la Justicia de \u00a0Orden \u00a0P\u00fablico. \u00a0El \u00a014 \u00a0de \u00a0enero de este a\u00f1o envi\u00f3 a Medell\u00edn solicitud de \u00a0expedici\u00f3n \u00a0de \u00a0copias \u00a0del \u00a0proceso \u00a0y, en el mes de marzo, se le notific\u00f3 lo \u00a0relacionado \u00a0con \u00a0la \u00a0autorizaci\u00f3n \u00a0de \u00a0lo \u00a0pedido. \u00a0Como a la fecha nada le ha \u00a0llegado, \u00a0necesita \u00a0saber si se las expedir\u00e1n y remitir\u00e1n a la c\u00e1rcel de esta \u00a0ciudad \u00a0o si debe enviar a Medell\u00edn el valor de tales copias y de la remisi\u00f3n. \u00a0As\u00ed \u00a0mismo, \u00a0a \u00a0qu\u00e9 \u00a0despacho \u00a0se \u00a0enviar\u00eda \u00a0el \u00a0dinero\u201d \u00a0(fl. \u00a012 cno. 2), \u00a0petici\u00f3n que reiter\u00f3 el 11 de julio siguiente (fl. 26 Ib.). \u00a0\u00a0<\/p>\n<p>Fue \u00a0tan evidente la desidia de la Fiscal\u00eda \u00a0por \u00a0escuchar \u00a0los \u00a0planteamientos \u00a0del \u00a0procesado, que \u00e9ste, el 25 de abril de \u00a01994, \u00a0solicit\u00f3 \u00a0declarar \u00a0la \u00a0nulidad \u00a0de \u00a0lo \u00a0actuado \u00a0por \u00a0violaci\u00f3n de sus \u00a0garant\u00edas \u00a0 \u00a0 \u00a0fundamentales \u00a0 \u00a0 \u00a0(fl. \u00a0 \u00a0 \u00a0557 \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 ss. \u00a0 \u00a0 \u20131), \u00a0 exponiendo \u00a0entre\u00a0 \u00a0otras \u00a0cosas \u00a0que \u00a0se \u00a0le ha negado la solicitud de copias del expediente y, por tanto, \u00a0de \u00a0 conocer \u00a0 la \u00a0 acusaci\u00f3n \u00a0 \u201cpara \u00a0 ejercer \u00a0a \u00a0plenitud \u00a0mi \u00a0derecho \u00a0de \u00a0defensa\u201d,\u00a0 \u00a0 \u00a0sin \u00a0 \u00a0obtener \u00a0 \u00a0del \u00a0 \u00a0organismo \u00a0 \u00a0acusador \u00a0 \u00a0respuesta \u00a0alguna. \u00a0\u00a0<\/p>\n<p>A \u00a0ello, \u00a0el \u00a015 de julio de 1994 el juzgado \u00a0regional \u00a0respondi\u00f3 \u00a0mediante auto de sustanciaci\u00f3n, considerando \u201cque\u00a0 \u00a0el \u00a0tr\u00e1mite \u00a0procesal \u00a0se ha adelantado dentro de las normas constitucionales y \u00a0legales \u00a0que no se observa violaci\u00f3n alguna de derechos; adem\u00e1s el proceso fue \u00a0revisado \u00a0por \u00a0la \u00a0Fiscal\u00eda \u00a0delegada ante el Tribunal Nacional, por apelaci\u00f3n \u00a0interpuesta \u00a0contra \u00a0la \u00a0providencia de resoluci\u00f3n de acusaci\u00f3n (sic), que fue \u00a0debidamente \u00a0confirmada \u00a0en \u00a0todas \u00a0sus \u00a0partes\u201d, \u00a0de \u00a0cuyos \u00a0pronunciamientos \u00a0dispuso \u00a0 \u00a0expedir \u00a0 \u00a0copias \u00a0 \u00a0al \u00a0 \u00a0procesado \u00a0 \u00a0(fl. \u00a0 \u00a033 \u00a0 \u00a0y \u00a0 \u00a0ss. \u00a0 cno. \u00a03).\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Visto, \u00a0entonces, \u00a0que de manera objetiva se \u00a0configura \u00a0el \u00a0motivo \u00a0de \u00a0ineficacia planteado por el recurrente sin que exista \u00a0ning\u00fan \u00a0otro \u00a0medio \u00a0diverso \u00a0de \u00a0remediar el vicio, se casar\u00e1 parcialmente la \u00a0sentencia \u00a0impugnada, \u00a0y se declarar\u00e1 la nulidad de lo actuado en relaci\u00f3n con \u00a0dicho \u00a0procesado \u00a0a partir inclusive de la clausura del ciclo investigativo, con \u00a0exclusi\u00f3n \u00a0de los actos de prueba, a fin de asegurar el ejercicio de la defensa \u00a0t\u00e9cnica \u00a0en \u00a0la \u00a0fase \u00a0de \u00a0la \u00a0instrucci\u00f3n \u00a0que \u00a0habr\u00e1 de adelantar el Fiscal \u00a0instructor \u00a0correspondiente \u00a0a \u00a0quien \u00a0el \u00a0Tribunal de instancia remitir\u00e1 copia \u00a0integral del expediente. \u00a0\u00a0<\/p>\n<p>2.1.- Libertad del procesado. \u00a0<\/p>\n<p>La \u00a0declaraci\u00f3n \u00a0de \u00a0nulidad \u00a0parcial de la \u00a0actuaci\u00f3n \u00a0procesal \u00a0cumplida \u00a0en \u00a0relaci\u00f3n \u00a0con \u00a0el \u00a0procesado MIGUEL ANTONIO \u00a0CABRERA \u00a0G\u00d3MEZ, a partir de la providencia que dispuso la clausura del sumario, \u00a0hace \u00a0que \u00a0se \u00a0consolide \u00a0respecto \u00a0de \u00a0\u00e9l \u00a0la \u00a0causal \u00a0de libertad provisional \u00a0prevista \u00a0en el numeral 4\u00ba del art\u00edculo 365 de la ley 600 de 2000, consistente \u00a0en \u00a0haber \u00a0transcurrido \u00a0m\u00e1s de 180 d\u00edas de privaci\u00f3n efectiva de la libertad \u00a0sin que se hubiere calificado el m\u00e9rito del sumario. \u00a0\u00a0<\/p>\n<p>En \u00a0consecuencia, \u00a0la \u00a0Corte \u00a0dispondr\u00e1 \u00a0la \u00a0libertad \u00a0provisional, para cuyos efectos deber\u00e1 prestar cauci\u00f3n prendaria por \u00a0valor \u00a0de \u00a0quinientos \u00a0mil pesos ($ 500.000.oo), a nombre de esta Corporaci\u00f3n y \u00a0suscribir \u00a0diligencia \u00a0de compromiso en los t\u00e9rminos se\u00f1alados en el art\u00edculo \u00a0368 \u00a0del C\u00f3digo de Procedimiento Penal. Para estos efectos, y la expedici\u00f3n de \u00a0la \u00a0correspondiente \u00a0boleta \u00a0de \u00a0libertad, se comisiona al Juzgado Primero Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Itag\u00fci, ciudad en la cual se encuentra detenido el procesado \u00a0(fl. \u00a053 \u00a0cno. \u00a0Corte). \u00a0El \u00a0Juez \u00a0comisionado \u00a0advertir\u00e1 \u00a0que esta orden s\u00f3lo \u00a0produce \u00a0efectos \u00a0si CABRERA G\u00d3MEZ no es requerido por otra autoridad en virtud \u00a0de proceso diferente. \u00a0\u00a0<\/p>\n<p>Es de anotar, que el monto de la cauci\u00f3n se \u00a0fija \u00a0no \u00a0solamente teniendo en cuenta las condiciones econ\u00f3micas del procesado \u00a0referidas \u00a0en \u00a0su \u00a0indagatoria, \u00a0en la que dijo ser comerciante en textiles pero \u00a0carecer \u00a0de \u00a0bienes \u00a0de \u00a0fortuna, sino la gravedad de la conducta punible por la \u00a0que \u00a0 \u00a0se \u00a0 le \u00a0 procesa, \u00a0 como \u00a0 es \u00a0 el \u00a0 delito \u00a0 de \u00a0 secuestro \u00a0 extorsivo \u00a0agravado.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>3.- \u00a0A nombre del \u00a0procesado URIEL MONROY. \u00a0\u00a0<\/p>\n<p>Varios \u00a0defectos \u00a0de \u00a0orden \u00a0t\u00e9cnico \u00a0y \u00a0de \u00a0fundamentaci\u00f3n \u00a0presenta \u00a0el \u00a0cargo \u00a0postulado \u00a0al amparo de la causal primera, \u00a0cuerpo segundo, que conducen a su desestimaci\u00f3n por la Sala. \u00a0\u00a0<\/p>\n<p>En \u00a0primer \u00a0lugar, \u00a0si \u00a0bien \u00a0enuncia que el \u00a0sentenciador \u00a0incurri\u00f3 \u00a0en \u00a0error \u00a0de \u00a0derecho por falso juicio de legalidad al \u00a0haber \u00a0admitido \u00a0y \u00a0conferido \u00a0valor \u00a0probatorio \u00a0a la diligencia de indagatoria \u00a0rendida \u00a0por \u00a0MIGUEL \u00a0ANTONIO \u00a0CABRERA G\u00d3MEZ, en la que se\u00f1al\u00f3 a URIEL MONROY \u00a0como \u00a0uno \u00a0de \u00a0los \u00a0part\u00edcipes en el secuestro, sin cumplirse con la formalidad \u00a0del \u00a0juramento, \u00a0es \u00a0lo \u00a0cierto que se\u00a0 equivoca en indicar la disposici\u00f3n \u00a0procesal \u00a0que \u00a0estima \u00a0transgredida en cuanto cita el art\u00edculo 285 del estatuto \u00a0procesal \u00a0de 1991 que se refer\u00eda a la amonestaci\u00f3n previa al juramento y no el \u00a0357 \u00a0ejusdem \u00a0relativo \u00a0a \u00a0la necesidad de juramentar al imputado cuando declara \u00a0contra terceros. \u00a0\u00a0<\/p>\n<p>No \u00a0obstante, debe advertirse, que aunque es \u00a0cierto \u00a0que \u00a0CABRERA \u00a0G\u00d3MEZ en la diligencia de indagatoria hizo cargos a URIEL \u00a0MONROY \u00a0y \u00a0que \u00a0no \u00a0fue \u00a0juramentado \u00a0de \u00a0ellos, \u00a0\u00e9sto \u00a0no afecta la validez ni \u00a0eficacia \u00a0de \u00a0dicho \u00a0acto \u00a0procesal en su doble condici\u00f3n de medio de defensa y \u00a0medio \u00a0probatorio, \u00a0ya que la aplicaci\u00f3n de la f\u00f3rmula del juramento cuando el \u00a0imputado \u00a0 declara \u00a0 contra \u00a0 otro, \u00a0 tiene \u00a0alcance \u00a0restringido \u00a0frente \u00a0a \u00a0la \u00a0responsabilidad \u00a0penal \u00a0del \u00a0indagado \u00a0en \u00a0su condici\u00f3n de testigo\u00a0 por un \u00a0eventual \u00a0delito de falso testimonio y no respecto del m\u00e9rito probatorio de las \u00a0imputaciones \u00a0que \u00a0realice \u00a0sin \u00a0el \u00a0cumplimiento \u00a0de \u00a0dicha exigencia, como con \u00a0acierto es destacado por la Delegada. \u00a0\u00a0<\/p>\n<p>Para \u00a0responder \u00a0la \u00a0inquietud del libelista \u00a0preciso \u00a0resulta \u00a0recordar \u00a0lo dicho por la jurisprudencia sobre este particular \u00a0aspecto: \u00a0\u00a0<\/p>\n<p>\u201cDebe \u00a0expresar la Sala, en primer lugar, \u00a0que \u00a0aunque \u00a0la \u00a0indagatoria \u00a0es \u00a0en principio un medio de defensa a trav\u00e9s del \u00a0cual \u00a0la \u00a0persona \u00a0vinculada \u00a0al \u00a0proceso penal tiene la oportunidad de explicar \u00a0unos \u00a0hechos que se le atribuyen, obra igualmente como medio de prueba en cuanto \u00a0contribuye \u00a0a \u00a0aclarar \u00a0y a reconstruir lo sucedido.\u00a0 En tal orden de ideas \u00a0resulta \u00a0absurdo \u00a0se\u00f1alar \u00a0que \u00a0cuando \u00a0el imputado relata un acontecer y en su \u00a0exposici\u00f3n \u00a0declara \u00a0en \u00a0contra \u00a0de otro o de otros, la circunstancia de no ser \u00a0juramentado \u00a0 para \u00a0 volverlo \u00a0 a \u00a0interrogar \u00a0sobre \u00a0el \u00a0particular \u00a0impide \u00a0la \u00a0valoraci\u00f3n \u00a0de \u00a0su \u00a0indagatoria \u00a0y la circunstancia eventual de utilizarla como \u00a0medio \u00a0de \u00a0convicci\u00f3n \u00a0para \u00a0edificar \u00a0desde \u00a0el \u00a0punto de vista probatorio una \u00a0determinaci\u00f3n judicial. \u00a0\u00a0<\/p>\n<p>\u201cCierto \u00a0que el art\u00edculo 357 del C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0prescribe \u00a0como regla general en la realizaci\u00f3n de la \u00a0indagatoria \u00a0la \u00a0prohibici\u00f3n \u00a0de juramentar al imputado y como excepci\u00f3n la de \u00a0hacerlo \u00a0 \u00a0 \u00a0cuando \u00a0 \u00a0 \u00a0\u00e9ste \u00a0 \u00a0 \u2018declarare \u00a0 contra \u00a0 otro\u2019.\u00a0\u00a0 \u00a0En presencia de esta hip\u00f3tesis, sin embargo, la no- \u00a0imposici\u00f3n \u00a0del juramento en manera alguna traduce un vicio de la indagatoria y \u00a0menos \u00a0impide \u00a0la \u00a0apreciaci\u00f3n \u00a0de \u00a0su \u00a0contenido \u00a0total y en particular de las \u00a0declaraciones contra otros que all\u00ed se hagan. \u00a0\u00a0<\/p>\n<p>\u201cEl \u00a0sentido del juramento en el curso de \u00a0la \u00a0indagatoria, \u00a0en \u00a0cuanto su imposici\u00f3n\u00a0 se exige del hecho de declarar \u00a0en \u00a0contra \u00a0de otro, tiene que ver con la responsabilidad personal de quien hace \u00a0la \u00a0incriminaci\u00f3n, \u00a0con \u00a0la \u00a0no-impunidad \u00a0total \u00a0de sus aseveraciones, la cual \u00a0s\u00f3lo \u00a0lo \u00a0protege \u00a0hasta \u00a0el momento en que las explicaciones que realice en su \u00a0defensa \u00a0no \u00a0signifiquen \u00a0la \u00a0atribuci\u00f3n \u00a0de un hecho delictivo a otra persona, \u00a0caso \u00a0en \u00a0el \u00a0cual el juramento tiene por objeto convertirlo en testigo respecto \u00a0de \u00a0esa \u00a0afirmaci\u00f3n \u00a0y en consecuencia en eventual autor de falso testimonio en \u00a0el caso de no resultar cierta su incriminaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u201cNo obstante, reitera la Sala, la omisi\u00f3n \u00a0del \u00a0juramento \u00a0en \u00a0la \u00a0hip\u00f3tesis \u00a0examinada en ninguna forma hace nugatoria la \u00a0posibilidad \u00a0del \u00a0examen \u00a0integral \u00a0de \u00a0la \u00a0indagatoria \u00a0como \u00a0medio de prueba y \u00a0obviamente \u00a0la \u00a0de ser tomada como fundamento de cualquier determinaci\u00f3n dentro \u00a0del \u00a0proceso \u00a0penal, \u00a0incluidas \u00a0naturalmente \u00a0la \u00a0acusaci\u00f3n y la sentencia. Lo \u00a0\u00fanico \u00a0que \u00a0propicia tal tipo de irregularidad, ya se dijo, es la imposibilidad \u00a0de \u00a0derivar responsabilidad penal en contra de quien incrimine falsamente a otro \u00a0en \u00a0el \u00a0marco de dicha diligencia de vinculaci\u00f3n procesal\u201d (Cfr. Sentencia de \u00a0casaci\u00f3n octubre 22 de 1998. M. P. Mej\u00eda Escobar. Rad. 10934). \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>A m\u00e1s de lo anterior, debe destacarse que el \u00a0actor \u00a0no \u00a0se \u00a0esfuerza en demostrar c\u00f3mo la omisi\u00f3n de juramentar al indagado \u00a0repercuti\u00f3 \u00a0negativamente \u00a0en la declaraci\u00f3n de responsabilidad de su asistido \u00a0y \u00a0por el contrario se dedica a cuestionar el m\u00e9rito persuasivo conferido en el \u00a0fallo \u00a0a \u00a0la indagatoria rendida por MIGUEL ANTONIO CABRERA G\u00d3MEZ, enlaz\u00e1ndolo \u00a0con \u00a0la \u00a0credibilidad \u00a0que \u00a0a su criterio merece lo expuesto por su asistido, al \u00a0tiempo \u00a0que \u00a0pretende \u00a0justificar \u00a0la mentira en que incurri\u00f3 y que el Tribunal \u00a0detect\u00f3 \u00a0 al \u00a0 ponderar \u00a0 la \u00a0 indagatoria \u00a0 de \u00a0\u00e9ste, \u00a0pero \u00a0sin \u00a0denotar \u00a0la \u00a0configuraci\u00f3n de un concreto error probatorio. \u00a0\u00a0<\/p>\n<p>A \u00a0este \u00a0respecto, \u00a0pertinente \u00a0resulta \u00a0la \u00a0consideraci\u00f3n \u00a0de la Delegada cuyo criterio la Sala comparte, en el sentido que \u00a0\u201cde \u00a0aceptarse \u00a0a \u00a0manera de discusi\u00f3n, la existencia del yerro planteado por \u00a0el \u00a0se\u00f1or \u00a0defensor, \u00a0-error de derecho por falso juicio de legalidad, frente a \u00a0los \u00a0 cargos \u00a0 formulados \u00a0por \u00a0Miguel \u00a0Antonio \u00a0Cabrera \u00a0a \u00a0Uriel \u00a0Monroy-, \u00a0al \u00a0casacionista \u00a0le \u00a0correspond\u00eda \u00a0desvirtuar \u00a0la totalidad de los fundamentos que \u00a0sustentan \u00a0la \u00a0sentencia \u00a0condenatoria, en este caso las versiones de los dem\u00e1s \u00a0coprocesados, \u00a0el \u00a0reconocimiento \u00a0de \u00a0la \u00a0v\u00edctima \u00a0del \u00a0secuestro, \u00a0y \u00a0toda la \u00a0estructura \u00a0 indiciaria, \u00a0 aspectos \u00a0 sobre \u00a0los \u00a0cuales \u00a0no \u00a0se \u00a0pronunci\u00f3 \u00a0el \u00a0recurrente\u201d.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Entonces, \u00a0ante \u00a0la \u00a0falta \u00a0de \u00a0fundamento y \u00a0raz\u00f3n en la postulaci\u00f3n del ataque, se desestima el cargo. \u00a0\u00a0<\/p>\n<p>4. Otras decisiones. \u00a0<\/p>\n<p>No \u00a0obstante existir motivos para investigar \u00a0disciplinariamente \u00a0al \u00a0doctor \u00a0Conrado \u00a0Osorno \u00a0Moncada \u00a0por \u00a0abandono \u00a0de \u00a0sus \u00a0obligaciones \u00a0como \u00a0defensor \u00a0del \u00a0procesado, \u00a0la \u00a0Sala se abstendr\u00e1 de expedir \u00a0copias \u00a0para \u00a0tales \u00a0efectos, \u00a0teniendo \u00a0en \u00a0cuenta que a la fecha la acci\u00f3n se \u00a0hallar\u00eda \u00a0prescrita \u00a0pues \u00a0la conducta omisiva se mantuvo hasta el 5 de octubre \u00a0de 1994, d\u00eda en que le fue revocado el poder (fl. 134 cno. 2). \u00a0\u00a0<\/p>\n<p>Como \u00a0quiera \u00a0que no se casar\u00e1 la sentencia \u00a0respecto \u00a0de los procesados recurrentes EDGAR ARIAS OROZCO y URIEL MONROY, y, en \u00a0consecuencia, \u00a0no \u00a0se \u00a0modifica la pena impuesta en el fallo, compete al Juez de \u00a0ejecuci\u00f3n \u00a0de \u00a0penas \u00a0y \u00a0medidas de seguridad realizar la redosificaci\u00f3n a que \u00a0hubiere \u00a0lugar, \u00a0a prop\u00f3sito de la entrada en vigencia del nuevo C\u00f3digo penal, \u00a0y \u00a0la \u00a0aplicaci\u00f3n del principio de favorabilidad (art\u00edculo 79.7 del C\u00f3digo de \u00a0procedimiento penal). \u00a0\u00a0<\/p>\n<p>Dado que no se sustituye la sentencia materia \u00a0de \u00a0impugnaci\u00f3n, \u00a0esta \u00a0determinaci\u00f3n \u00a0cobra \u00a0ejecutoria \u00a0con su proferimiento \u00a0(art. 187 de la ley 600 de 2000). \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0LA \u00a0CORTE \u00a0SUPREMA \u00a0DE JUSTICIA, SALA DE CASACION PENAL, \u00a0o\u00eddo \u00a0el \u00a0concepto del Procurador segundo delegado en lo penal, \u00a0administrando \u00a0justicia \u00a0en \u00a0nombre \u00a0de \u00a0la \u00a0Rep\u00fablica \u00a0y \u00a0por \u00a0autoridad de la \u00a0ley, \u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>PRIMERO. \u00a0CASAR \u00a0PARCIALMENTE\u00a0 la sentencia impugnada. \u00a0\u00a0<\/p>\n<p>SEGUNDO. DECRETAR \u00a0LA \u00a0NULIDAD \u00a0de \u00a0la \u00a0actuaci\u00f3n \u00a0procesal cumplida en relaci\u00f3n con el sindicado \u00a0MIGUEL \u00a0ANTONIO CABRERA G\u00d3MEZ, a partir inclusive de la resoluci\u00f3n de clausura \u00a0del ciclo investigativo. \u00a0\u00a0<\/p>\n<p>TERCERO. DISPONER \u00a0la \u00a0libertad \u00a0provisional \u00a0del \u00a0procesado \u00a0MIGUEL ANTONIO CABRERA G\u00d3MEZ, en los \u00a0t\u00e9rminos indicados en la parte considerativa de esta providencia. \u00a0\u00a0<\/p>\n<p>CUARTO. DESESTIMAR \u00a0las \u00a0demandas \u00a0de \u00a0casaci\u00f3n \u00a0presentadas \u00a0por \u00a0los defensores de los procesados \u00a0EDGAR ARIAS OROZCO y URIEL MONROY.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>En \u00a0 lo \u00a0 dem\u00e1s \u00a0 el \u00a0fallo \u00a0se \u00a0mantiene \u00a0inc\u00f3lume. \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Contra \u00a0 esta \u00a0 decisi\u00f3n \u00a0 no \u00a0 proceden \u00a0recursos. \u00a0\u00a0<\/p>\n<p>Comun\u00edquese\u00a0 y devu\u00e9lvase a la oficina \u00a0correspondiente. \u00a0\u00a0<\/p>\n<p>C\u00famplase. \u00a0<\/p>\n<p>ALVARO \u00a0 O. \u00a0 P\u00c9REZ \u00a0PINZ\u00d3N \u00a0\u00a0<\/p>\n<p>FERNANDO \u00a0 \u00a0 \u00a0 E. \u00a0 \u00a0 \u00a0 ARBOLEDA \u00a0RIPOLL\u00a0\u00a0\u00a0\u00a0 JORGE E. C\u00d3RDOBA POVEDA \u00a0\u00a0<\/p>\n<p>HERMAN \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 GAL\u00c1N \u00a0CASTELLANOS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0CARLOS \u00a0A. \u00a0G\u00c1LVEZ \u00a0ARGOTE \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JORGE \u00a0 \u00a0 \u00a0 \u00a0A. \u00a0 \u00a0 \u00a0 \u00a0G\u00d3MEZ \u00a0GALLEGO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0EDGAR LOMBANA TRUJILLO\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>MARINA \u00a0 \u00a0 \u00a0 \u00a0PULIDO \u00a0 \u00a0 \u00a0 \u00a0DE \u00a0BAR\u00d3N\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0YESID RAM\u00cdREZ BASTIDAS \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 14065 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CORTE SUPREMA DE JUSTICIA \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0SALA DE CASACION PENAL \u00a0\u00a0 Magistrado Ponente: \u00a0 Dr. \u00a0FERNANDO \u00a0E. \u00a0ARBOLEDA RIPOLL \u00a0\u00a0 Aprobado \u00a0 \u00a0 \u00a0 \u00a0acta \u00a0 \u00a0 \u00a0 \u00a0No. \u00a0149\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0 Bogot\u00e1, D. C.,\u00a0 veintiuno de noviembre \u00a0del a\u00f1o dos mil dos. \u00a0\u00a0 Resuelve [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5558","post","type-post","status-publish","format-standard","hentry","category-10"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/5558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=5558"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/5558\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=5558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=5558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=5558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}