{"id":54543,"date":"2023-10-31T14:54:18","date_gmt":"2023-10-31T14:54:18","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/10\/31\/stp2585-2021\/"},"modified":"2023-10-31T14:54:18","modified_gmt":"2023-10-31T14:54:18","slug":"stp2585-2021","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/10\/31\/stp2585-2021\/","title":{"rendered":"STP2585-2021"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>GERSON \u00a0CHAVERRA CASTRO \u00a0<\/p>\n<p>Magistrado \u00a0ponente \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>STP2585-2021 \u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0n\u00b0 114625 \u00a0<\/p>\n<p>Acta \u00a0No 026 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D.C., once (11) de febrero de dos mil veintiuno (2021) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ASUNTO \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La Sala decide la \u00a0impugnaci\u00f3n presentada por COLPENSIONES y Protecci\u00f3n \u00a0S.A., contra el fallo proferido el 6 de noviembre de 2020, por la \u00a0mayor\u00eda de la Sala \u00a0de Casaci\u00f3n Laboral, \u00a0a \u00a0trav\u00e9s del cual ampar\u00f3 los derechos fundamentales \u00a0a la seguridad \u00a0social, igualdad, acceso a la administraci\u00f3n de justicia y \u00a0debido proceso de ASTRID ESCOBAR JURADO, vulnerados por la Sala \u00a0Laboral del Tribunal Superior del Distrito Judicial de Bogot\u00e1. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Al \u00a0tr\u00e1mite fueron \u00a0vinculados las partes e intervinientes en el ordinario laboral con \u00a0radicaci\u00f3n n.\u00ba 11001-3105-002-2018-0037901. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. HECHOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Y FUNDAMENTOS DE LA DEMANDA \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Los \u00a0sucesos que motivaron la solicitud de amparo constitucional y las \u00a0pretensiones de la interesada fueron rese\u00f1ados por la Sala de \u00a0Casaci\u00f3n Laboral de la siguiente forma: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00abLa \u00a0ciudadana Astrid Escobar Jurado instaura acci\u00f3n de tutela con \u00a0el prop\u00f3sito de obtener el amparo de sus derechos \u00a0fundamentales a la igualdad, acceso a la administraci\u00f3n de \u00a0justicia, debido proceso, m\u00ednimo vital, libre selecci\u00f3n \u00a0del r\u00e9gimen pensional y seguridad social, presuntamente \u00a0vulnerados por la autoridad convocada. \u00a0<\/p>\n<p>Para \u00a0el efecto, y en lo que a este tr\u00e1mite interesa, manifest\u00f3 \u00a0que promovi\u00f3 proceso ordinario laboral contra Colpensiones, \u00a0Porvenir S.A. y Protecci\u00f3n S. A., a fin de que se declarara la \u00a0nulidad (ineficacia) del traslado del R\u00e9gimen de Prima Media \u00a0con Prestaci\u00f3n Definida \u2013RPM al R\u00e9gimen de Ahorro \u00a0Individual con Solidaridad \u2013RAIS a trav\u00e9s de Porvenir \u00a0S.A., toda vez que, en su sentir, no se le brind\u00f3 informaci\u00f3n \u00a0completa y comprensible sobre los riesgos del cambio de r\u00e9gimen. \u00a0<\/p>\n<p>El \u00a0conocimiento del asunto correspondi\u00f3 al Juzgado Segundo \u00a0Laboral del Circuito de Bogot\u00e1, autoridad que mediante \u00a0sentencia de 27 de junio de 2019 accedi\u00f3 a las pretensiones de \u00a0la demanda. Inconformes con la anterior decisi\u00f3n, los \u00a0apoderados de Colpensiones y Porvenir S.A. interpusieron recurso de \u00a0apelaci\u00f3n. \u00a0<\/p>\n<p>En \u00a0fallo de 4 de septiembre de 2020, la Sala Laboral del Tribunal \u00a0Superior de Bogot\u00e1, revoc\u00f3 la determinaci\u00f3n de \u00a0primera instancia y, en su lugar, absolvi\u00f3 a las entidades de \u00a0todas las s\u00faplicas elevadas en su contra. \u00a0<\/p>\n<p>Aleg\u00f3 \u00a0que el ad quem desconoci\u00f3 el precedente jurisprudencial de la \u00a0Sala de Casaci\u00f3n Laboral aplicable a la nulidad o ineficacia \u00a0de traslado \u201cdesde hace m\u00e1s de 10 a\u00f1os, por la no \u00a0valoraci\u00f3n en conjunto del material probatorio obrante en el \u00a0expediente, y el desconocimiento de las disposiciones creadas por el \u00a0legislador sobre la materia, pues con el material probatorio obrante \u00a0en el expediente, es f\u00e1cil concluir que la AFP Porvenir no le \u00a0brind\u00f3 una informaci\u00f3n clara, cierta y comprensible, \u00a0respecto de caracter\u00edsticas, condiciones, diferencias, riesgos \u00a0y consecuencias del traslado de r\u00e9gimen, no siendo suficiente \u00a0la firma de un formulario para dar por sentado que se le brind\u00f3 \u00a0la asesor\u00eda pertinente y adecuada como lo concluy\u00f3 el \u00a0cuerpo colegiado.\u201d \u00a0<\/p>\n<p>Critic\u00f3 \u00a0que el Tribunal bas\u00f3 su decisi\u00f3n en \u00abla ausencia \u00a0de participaci\u00f3n de Colpensiones en el acto de traslado, y la \u00a0falta de demostraci\u00f3n de perjuicios a cargo de PORVENIR S.A., \u00a0adem\u00e1s de determinarse que Colpensiones, no particip\u00f3 \u00a0en el acto de afiliaci\u00f3n al RAIS, porque ni patrocin\u00f3 \u00a0su traslado, ni intervino en dichas diligencias\u00bb. por lo que \u00a0concluy\u00f3: \u00a0<\/p>\n<p>Se \u00a0declarar\u00e1 la falta de presupuestos procesales para aplicar el \u00a0art\u00edculo 271 de la Ley 100 de 1993; se revocar\u00e1n las \u00a0condenas impuestas a PORVENIR S.A., por la ausencia de la \u00a0demostraci\u00f3n de perjuicios causados con ocasi\u00f3n de la \u00a0afiliaci\u00f3n, a la luz de lo dispuesto en el art\u00edculo 10 \u00a0del Decreto 720 de 1994 y, se revocar\u00e1n las condenas impuestas \u00a0a Colpensiones, por ser ajena a la decisi\u00f3n de traslado de \u00a0r\u00e9gimen tomada por el afiliado, ajena a las invocadas \u00a0deficiencias en el deber de informaci\u00f3n, y por no participar \u00a0en acto contractual alguno, que le pueda imponer restituciones de \u00a0ninguna clase a la luz del art\u00edculo 1746 del C\u00f3digo \u00a0Civil, habida cuenta que el acto de afiliaci\u00f3n no tiene \u00a0car\u00e1cter contractual y la norma en cita no aplica a la \u00a0regulaci\u00f3n de actos de la seguridad social que tiene \u00a0regulaci\u00f3n propia (\u2026). \u00a0<\/p>\n<p>Quedando \u00a0abiertamente vulnerado el derecho fundamental de igualdad de trato \u00a0frente a la administraci\u00f3n de justicia que deben tener sus \u00a0usuarios, pues en este caso particular se desconoci\u00f3 \u00a0abiertamente el precedente jurisprudencial construido de manera \u00a0pac\u00edfica por la honorable Corte Suprema de Justicia \u2013 \u00a0Sala de Casaci\u00f3n Laboral, desconociendo en tal sentido lo \u00a0sentado por la corte en cuanto que el formulario de afiliaci\u00f3n \u00a0no es suficiente para acreditar un consentimiento informado, que es \u00a0deber de las APFS informar acerca de las caracter\u00edsticas, \u00a0ventajas y desventajas del traslado, de la inversi\u00f3n de la \u00a0carga de la prueba en favor del afiliado, y de la aplicaci\u00f3n \u00a0del precedente sin importar si se tiene o no el r\u00e9gimen de \u00a0transici\u00f3n, o un derecho consolidado. \u00a0<\/p>\n<p>De \u00a0conformidad con lo anterior, solicita el amparo de sus prerrogativas \u00a0constitucionales y, en consecuencia, se revoque la sentencia de 4 de \u00a0septiembre de 2020, para que, en su lugar, se confirme la decisi\u00f3n \u00a0de primera instancia.\u00bb \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>2. FALLO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0RECURRIDO \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El \u00a0A \u00a0quo \u00a0constitucional, en providencia de 6 de noviembre de \u00a02020, luego \u00a0de flexibilizar el requisito de la subsidiariedad, ampar\u00f3 \u00a0las prerrogativas constitucionales de la actora tras considerar que \u00a0la Sala Laboral del Tribunal Superior de Bogot\u00e1, en el fallo \u00a0de segunda instancia atacado, desconoci\u00f3 el \u00a0precedente jurisprudencial1 \u00a0fijado por la m\u00e1xima autoridad judicial en material del \u00a0trabajo y de la seguridad social. Al respecto resolvi\u00f3: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00abPRIMERO: \u00a0CONCEDER \u00a0la tutela de los derechos fundamentales a la seguridad social, \u00a0igualdad, acceso a la administraci\u00f3n de justicia y debido \u00a0proceso de ASTRID \u00a0ESCOBAR JURADO. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>SEGUNDO: \u00a0DEJAR SIN EFECTO \u00a0la sentencia de 4 de septiembre de 2020, para en su lugar, ordenar a \u00a0la SALA \u00a0LABORAL DEL TRIBUNAL SUPERIOR DEL DISTRITO JUDICIAL DE BOGOT\u00c1, \u00a0que en el t\u00e9rmino de diez (10) d\u00edas contados a partir \u00a0de la fecha que reciba el expediente, profiera nueva decisi\u00f3n, \u00a0teniendo en cuenta lo expuesto en la parte motiva de esta \u00a0providencia. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>TERCERO: \u00a0EXHORTAR \u00a0a la SALA \u00a0LABORAL DEL TRIBUNAL \u00a0SUPERIOR \u00a0DEL DISTRITO JUDICIAL DE BOGOT\u00c1 \u00a0para que en lo sucesivo acate el precedente judicial emanado de esta \u00a0Corporaci\u00f3n.\u00bb (Negrilla \u00a0original del texto) \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El \u00a0razonamiento del A quo consisti\u00f3 en deducir que, en la \u00a0sentencia atacada se verifica la causal espec\u00edfica de \u00a0procedencia de la tutela contra providencias judiciales denominada \u00a0desconocimiento \u00a0del precedente judicial, \u00a0en tanto, la Colegiatura accionada se apart\u00f3 del precedente \u00a0que rige la materia sin argumentos suficientes. Explic\u00f3 que, \u00a0de acuerdo con la jurisprudencia definida en la materia, la elecci\u00f3n \u00a0a cualquiera de los dos reg\u00edmenes pensionales existentes debe \u00a0fundarse en una decisi\u00f3n libre y voluntaria, debidamente \u00a0asesorada por parte de las administradoras de pensiones al afiliado, \u00a0que le permita tener los elementos de juicio necesarios para advertir \u00a0la trascendencia del traslado, sin importar si la persona es o no \u00a0beneficiaria del r\u00e9gimen de transici\u00f3n o si est\u00e1 \u00a0pr\u00f3ximo a obtener la pensi\u00f3n, so pena de declararse la \u00a0ineficacia del traslado de r\u00e9gimen. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En \u00a0ese sentido, explic\u00f3 que las motivaciones del Tribunal se \u00a0remitieron a que no se demostr\u00f3 la existencia de un perjuicio \u00a0y a que Colpensiones no particip\u00f3 en la diligencia de traslado \u00a0ni en los hechos que se recriminan por falta de informaci\u00f3n al \u00a0respecto; las cuales, destac\u00f3 la Sala de Casaci\u00f3n \u00a0Laboral, desconocen los presupuestos sentados por la jurisprudencia \u00a0como aquellos a analizar en estos casos y que se cifran a: i) el \u00a0deber de informaci\u00f3n a cargo de las administradoras de fondos \u00a0de pensiones; ii) que no basta para dar por satisfecho esa obligaci\u00f3n \u00a0el diligenciamiento del formato de afiliaci\u00f3n; iii) que la \u00a0carga de la prueba en estos eventos recae en la demandada y no en el \u00a0demandante; y, iv) la ineficacia de la afiliaci\u00f3n no depende \u00a0de que el afiliado tenga una expectativa de pensi\u00f3n o un \u00a0derecho causado. \u00a0<\/p>\n<p>Para \u00a0tal efecto, hizo \u00e9nfasis en el hecho de que el Tribunal no \u00a0despleg\u00f3 ning\u00fan an\u00e1lisis relacionado con el \u00a0segundo punto de los anteriormente referidos y que, de forma indebida \u00a0analiz\u00f3 \u00abla \u00a0figura \u00a0de la ineficacia de pleno derecho [que] \u00a0es propia de los actos regulados en el estatuto comercial, los cuales \u00a0nada tienen que ver \u2018con el acto de afiliaci\u00f3n a un \u00a0r\u00e9gimen pensional\u2019, pues \u00a0esta Sala en sentencia CSJ \u00a0SL1688-2019 indic\u00f3 que la \u00a0reacci\u00f3n del ordenamiento jur\u00eddico (arts. 271 y 272 de \u00a0la Ley 100 de 1993) a la afiliaci\u00f3n desinformada es la \u00a0ineficacia, o la exclusi\u00f3n de todo efecto jur\u00eddico del \u00a0acto de traslado.\u00bb \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De \u00a0manera que, ante el desconocimiento del precedente judicial por parte \u00a0del Tribunal en la decisi\u00f3n censurada, la Sala hom\u00f3loga \u00a0determin\u00f3 dejar sin efectos la sentencia del Tribunal. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>3. LAS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0IMPUGNACIONES \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. La \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Directora de Asuntos Constitucionales de COLPENSIONES, parti\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0por indicar que los jueces tienen la potestad de apartarse de la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0jurisprudencia como expresi\u00f3n de su autonom\u00eda, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0agotando la carga exigida para ello, soporte con el que cuenta la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sentencia revocada, pues cumple con el est\u00e1ndar \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0argumentativo al satisfacer los requisitos de transparencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0suficiencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(SU354-5017). \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Agreg\u00f3, \u00a0que la sentencia atacada no cumple las causales generales y \u00a0espec\u00edficas de procedibilidad de la acci\u00f3n de tutela \u00a0contra providencias judiciales; haciendo hincapi\u00e9 en el de la \u00a0subsidiariedad, \u00a0en tanto que no se agot\u00f3 el recurso de casaci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por \u00a0otra parte, expuso que, de acuerdo con las reglas del traslado de \u00a0r\u00e9gimen de pensiones establecidas por la Corte Constitucional \u00a0(C-1024-2004 y T-427-210), se busca evitar con los cambios de r\u00e9gimen \u00a0la descapitalizaci\u00f3n del sistema. E igualmente, que es \u00a0comprensible que personas al momento de la creaci\u00f3n del \u00a0sistema general de pensiones adujeran no haber comprendido las \u00a0consecuencias del traslado, empero, no en este caso, dado que la \u00a0accionante \u201cya \u00a0conoc\u00eda el funcionamiento de las AFP\u2019S\u201d \u00a0e hizo el cambio muchos a\u00f1os despu\u00e9s de dicha creaci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Indic\u00f3 \u00a0tambi\u00e9n, que no tiene raz\u00f3n el A \u00a0quo \u00a0al indicar que le asiste la carga de la prueba de suministrar la \u00a0informaci\u00f3n al afiliado sobre las consecuencias y dem\u00e1s \u00a0aspectos de la variaci\u00f3n del r\u00e9gimen pensional, y a la \u00a0par, con respecto al criterio de que, para recuperar el r\u00e9gimen \u00a0de prima media, se requiere cumplir los requisitos del r\u00e9gimen \u00a0de transici\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Finaliz\u00f3 \u00a0su exposici\u00f3n, expresando que no se satisfacen los requisitos \u00a0del perjuicio irremediable y que la decisi\u00f3n proferida en sede \u00a0de tutela afecta no solo la autonom\u00eda judicial del juez \u00a0ordinario, sino igualmente el principio de cosa juzgada, y genera un \u00a0grave impacto fiscal y la sostenibilidad financiera del sistema \u00a0pensional. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>2. Por \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0su parte, la representante legal de Protecci\u00f3n S.A. adujo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0igualmente que el Tribunal, bajo el principio de autonom\u00eda \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0judicial, cumpli\u00f3 con la carga argumental necesaria para \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0apartarse del precedente, al arg\u00fcir que el asunto conocido en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el proceso ordinario obedec\u00eda a hechos dis\u00edmiles a \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0los del precedente y, por ende, no susceptibles de resolverse a \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0trav\u00e9s de este, al igual que, anunci\u00f3 el antecedente \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del cual se apartaba y las razones para ello. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Agreg\u00f3 \u00a0que en el tr\u00e1mite ordinario se acredit\u00f3 que la \u00a0demandante obtuvo la informaci\u00f3n necesaria acerca de las \u00a0condiciones y consecuencias del r\u00e9gimen al que se trasladar\u00eda, \u00a0as\u00ed como las diferencias entre uno y otro sistema, por lo que, \u00a0su elecci\u00f3n se realiz\u00f3 de forma libre, voluntaria e \u00a0informada. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Finalmente, \u00a0indic\u00f3 que, en caso de estudiarse el asunto de fondo, se \u00a0remit\u00eda a los argumentos expuestos en el proceso laboral \u00a0ordinario2. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4. \u00a0CONSIDERACIONES \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1. De conformidad \u00a0con lo previsto en el art\u00edculo 2.2.3.1.2.4 del Decreto 1069 de \u00a02015, modificado por el canon 2\u00ba del Decreto 1983 de 2017, en \u00a0concordancia con el art\u00edculo 44 del reglamento interno de esta \u00a0Corporaci\u00f3n, es competente esta Sala para pronunciarse sobre \u00a0la impugnaci\u00f3n interpuesta, en tanto lo es en relaci\u00f3n \u00a0con la sentencia de tutela adoptada en primera instancia por la Sala \u00a0de Casaci\u00f3n Laboral. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2. \u00a0Suficiente ha sido la divulgaci\u00f3n del canon 86 de la \u00a0Constituci\u00f3n Pol\u00edtica, en cuanto establece que toda \u00a0persona tiene derecho a promover acci\u00f3n de tutela ante los \u00a0jueces con miras a obtener la protecci\u00f3n inmediata de sus \u00a0derechos constitucionales fundamentales, cuando por acci\u00f3n u \u00a0omisi\u00f3n le sean vulnerados o amenazados por cualquier \u00a0autoridad p\u00fablica o por particulares en los casos previstos de \u00a0forma expresa en la ley, siempre que no exista otro medio de defensa \u00a0judicial o, existiendo, se utilice como mecanismo transitorio para \u00a0evitar la materializaci\u00f3n de un perjuicio de car\u00e1cter \u00a0irremediable. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>3. En el asunto \u00a0sub \u00a0ex\u00e1mine, \u00a0Astrid Escobar Jurado solicita \u00a0por v\u00eda de tutela dejar sin efecto la providencia emitida en \u00a0segunda instancia el 4 de septiembre de 2020, por la Sala Laboral del \u00a0Tribunal Superior de Bogot\u00e1, mediante la cual, revoc\u00f3 \u00a0el fallo del 27 de junio de 2019 del Juzgado Segundo Laboral del \u00a0Circuito del mismo distrito judicial, que accedi\u00f3 a la \u00a0pretensi\u00f3n de invalidar el traslado de r\u00e9gimen \u00a0pensional. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4. De manera que, \u00a0el \u00a0problema jur\u00eddico por resolver se contrae a determinar si, \u00a0como lo concluy\u00f3 el A quo constitucional, el referido Tribunal \u00a0emiti\u00f3 una sentencia desconocedora del precedente judicial \u00a0dictado por la Sala de Casaci\u00f3n Laboral atinente a la \u00a0ineficacia del traslado de r\u00e9gimen pensional por la falta \u00a0informaci\u00f3n de los beneficios y desventajas del acto jur\u00eddico. \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>5. \u00a0Sobre el particular, se anticipa que se confirmar\u00e1 la \u00a0sentencia de primera instancia, toda vez que la Sala Laboral del \u00a0Tribunal Superior de Bogot\u00e1 en su sentencia, desconoci\u00f3 \u00a0el precedente judicial del \u00f3rgano de cierre de la jurisdicci\u00f3n \u00a0ordinaria en materia de traslados de r\u00e9gimen pensional. En ese \u00a0orden de ideas, se analizar\u00e1n los presupuestos generales de \u00a0procedibilidad de la acci\u00f3n, para luego exponer las razones de \u00a0la configuraci\u00f3n de la causal de procedibilidad de la acci\u00f3n \u00a0contra sentencias judiciales aludida. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>6. En \u00a0ese contexto, debe recordarse que acorde con la jurisprudencia de la \u00a0Corte Constitucional (Cfr. Sentencias: C-590 \u00a0de 2005, SU-195 de 2012 y T-137 \u00a0de 2017, entre otras) \u00a0la acci\u00f3n de tutela contra providencias judiciales solamente \u00a0es procedente de manera excepcional y, siempre que se cumplan ciertos \u00a0y rigurosos presupuestos de procedibilidad, agrupados en (i) \u00a0requisitos generales; y (ii) \u00a0causales espec\u00edficas. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Los primeros, se \u00a0concretan a: (i) \u00a0que \u00a0la cuesti\u00f3n que se discuta resulte de evidente relevancia \u00a0constitucional; (ii) \u00a0se haya agotado todos los medios \u2013ordinarios y extraordinarios\u2013 \u00a0de defensa judicial al alcance de la persona afectada, salvo que se \u00a0trate de evitar la consumaci\u00f3n de un perjuicio iusfundamental \u00a0irremediable; (iii) \u00a0se cumpla el requisito de la inmediatez, es decir, que la tutela se \u00a0hubiere interpuesto en un t\u00e9rmino razonable y proporcionado a \u00a0partir del hecho que origin\u00f3 la vulneraci\u00f3n; (iv) \u00a0cuando se trate de una irregularidad procesal, debe quedar claro que \u00a0la misma tiene un efecto decisivo o determinante en la sentencia que \u00a0se impugna y que afecta los derechos fundamentales de la parte \u00a0actora; (v) \u00a0la parte accionante identifique de manera razonable tanto los hechos \u00a0que generaron la afectaci\u00f3n como los derechos vulnerados y que \u00a0se hubiese alegado en el proceso judicial siempre que esto hubiere \u00a0sido posible y; (vi) \u00a0que no se trate de sentencias de tutela. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Mientras que los \u00a0segundos, implican la demostraci\u00f3n de por lo menos uno de los \u00a0siguientes vicios: a) \u00a0un \u00a0defecto org\u00e1nico \u00a0(falta de competencia del funcionario judicial); b) \u00a0un \u00a0defecto procedimental absoluto \u00a0(desconocer el procedimiento legal establecido); c) \u00a0un \u00a0defecto f\u00e1ctico \u00a0(que la decisi\u00f3n carezca de fundamentaci\u00f3n probatoria); \u00a0d) \u00a0un \u00a0defecto material o sustantivo \u00a0(aplicar normas inexistentes o inconstitucionales); e) \u00a0un \u00a0error inducido \u00a0(que la decisi\u00f3n judicial se haya adoptado con base en el \u00a0enga\u00f1o de un tercero); f) \u00a0una \u00a0decisi\u00f3n sin motivaci\u00f3n \u00a0(ausencia de fundamentos f\u00e1cticos y jur\u00eddicos en la \u00a0providencia); g) \u00a0un \u00a0desconocimiento del precedente; \u00a0y, h) \u00a0la violaci\u00f3n \u00a0directa de la Constituci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Aplicando las \u00a0premisas jurisprudenciales antes expuestas al caso concreto, debe \u00a0se\u00f1alarse que en lo que ata\u00f1e a las exigencias de \u00a0car\u00e1cter general, las mismas se cumplen, toda vez que el \u00a0caso es de relevancia constitucional, pues lo que es objeto de debate \u00a0es la vulneraci\u00f3n de los derechos fundamentales a la seguridad \u00a0social, igualdad, acceso a la administraci\u00f3n de justicia y \u00a0debido proceso, \u00a0derivada del fallo proferido por la Sala Laboral del Tribunal \u00a0Superior del Distrito Judicial de Bogot\u00e1. Del mismo modo, la \u00a0accionante identific\u00f3 \u00a0con suficiencia los fundamentos f\u00e1cticos y las pretensiones, \u00a0as\u00ed como los derechos que considera vulnerados, adem\u00e1s, \u00a0no se discute por este cauce una sentencia de tutela. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En cuanto al \u00a0agotamiento previo de todos los mecanismos de defensa judicial, si \u00a0bien la accionante desisti\u00f3 del recurso de casaci\u00f3n que \u00a0promovi\u00f3 contra el fallo censurado, lo cual dar\u00eda a \u00a0lugar a desestimar el amparo por \u00a0desconocimiento del principio de subsidiariedad, considera la Sala \u00a0que, contrario a lo esgrimido por la directora de asuntos \u00a0constitucionales de Colpensiones, \u00e9ste debe flexibilizarse en \u00a0atenci\u00f3n a las particularidades del caso concreto, en \u00a0especial, ante la necesidad de procurar la protecci\u00f3n de los \u00a0derechos fundamentales invocados por \u00a0la \u00a0evidente concurrencia de la causal espec\u00edfica de procedencia \u00a0del amparo relacionada con el desconocimiento \u00a0del precedente, \u00a0lo cual torna necesaria la intervenci\u00f3n extraordinaria del \u00a0juez constitucional3. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sobre esa \u00a0tem\u00e1tica, la Corte Constitucional, en sentencia CC T-441-2018, \u00a0indic\u00f3: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>[\u2026] La \u00a0jurisprudencia de esta Corte ha se\u00f1alado que existen dos \u00a0eventos en los que la acci\u00f3n de tutela interpuesta contra una \u00a0providencia judicial resulta procedente aunque no se haya agotado el \u00a0recurso extraordinario de casaci\u00f3n: \u201c(i) si la situaci\u00f3n \u00a0material de existencia y el asunto a tratar del accionante, lo \u00a0convierten en una carga desproporcionada4 \u00a0y, (ii) \u00a0cuando resulta evidente que existe una vulneraci\u00f3n de derechos \u00a0fundamentales y por ende, no admitir la procedencia de la acci\u00f3n \u00a0de tutela implicar\u00eda que lo formal prevalecer\u00eda ante lo \u00a0sustancial, desconociendo as\u00ed la obligaci\u00f3n estatal de \u00a0garantizar la efectividad de los derechos fundamentales5 \u00a0y la prevalencia del derecho sustancial6, \u00a0comoquiera que la aplicaci\u00f3n severa de esta regla \u2018causar\u00eda \u00a0un da\u00f1o de mayor entidad constitucional que el que se \u00a0derivar\u00eda del desconocimiento del criterio general \u00a0enunciado\u20197\u201d8 \u00a0(Negrillas \u00a0fuera del texto) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Conforme con lo \u00a0anterior, aun cuando se reconoce que el camino para debatir el tema \u00a0es el recurso extraordinario de casaci\u00f3n -como se ha intentado \u00a0en otros casos-, se reitera, en este asunto se flexibiliza, ante la \u00a0necesidad de salvaguardar derechos fundamentales de la accionante, \u00a0quien busca revocar una decisi\u00f3n contraria a la jurisprudencia \u00a0decantada por la m\u00e1xima autoridad de la jurisdicci\u00f3n \u00a0ordinaria en lo laboral, frente a la ineficacia del traslado de \u00a0r\u00e9gimen pensional. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Y, en lo atinente \u00a0a la inmediatez, se tiene que la presente controversia se enmarca en \u00a0un tema ligado a la seguridad social, en el que si bien no se debate \u00a0el reconocimiento pensional o el monto de la mesada (prestaci\u00f3n \u00a0peri\u00f3dica), sino la ineficacia del traslado de r\u00e9gimen, \u00a0se puede sostener que los efectos de la decisi\u00f3n adoptada se \u00a0mantienen en el tiempo y amenaza con causar un perjuicio mayor, pues \u00a0al tratarse de una decisi\u00f3n jurisdiccional que, en apariencia, \u00a0se ha apartado deliberadamente de un precedente judicial, sus \u00a0consecuencias amenazan con consolidar una situaci\u00f3n que podr\u00eda \u00a0traducirse en una afectaci\u00f3n definitiva de los derechos \u00a0fundamentales a la igualdad y m\u00ednimo vital de la accionante. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Adicional a ello, \u00a0la acci\u00f3n de tutela se emple\u00f3 en un t\u00e9rmino \u00a0razonable, pues como lo apreci\u00f3 el A \u00a0quo, \u00a0la sentencia atacada data de 4 de septiembre de 2020 y la actora \u00a0acudi\u00f3 a este tr\u00e1mite preferente el 20 de octubre del \u00a0mismo a\u00f1o, es decir, poco mas de un mes posterior a la emisi\u00f3n \u00a0de la providencia que busca dejar sin efectos. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7. Entonces, \u00a0constatado el cumplimiento de los requisitos en menci\u00f3n, se \u00a0analiza la concurrencia de la causal de procedibilidad referida al \u00a0\u00abdesconocimiento \u00a0del precedente\u00bb \u00a0el cual constituye el argumento medular de la s\u00faplica de \u00a0amparo. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.1. En primer \u00a0lugar, se hace necesario destacar que, conforme con lo consagrado en \u00a0los art\u00edculos 234, 237 y 241 de la Constituci\u00f3n \u00a0Pol\u00edtica, la Corte Suprema de Justicia y el Consejo de Estado, \u00a0como tribunales de cierre de las jurisdicciones ordinaria y \u00a0contencioso administrativa, al igual que la Corte Constitucional, \u00a0como \u00f3rgano encargado de salvaguardar la supremac\u00eda e \u00a0integridad de la Carta, tienen el deber de unificar la jurisprudencia \u00a0al interior de sus jurisdicciones, de tal manera que los \u00a0pronunciamientos que emitan se conviertan en precedente \u00a0judicial de obligatorio cumplimiento. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En tal senda, la \u00a0Corte Constitucional ha definido el precedente judicial como \u00abla \u00a0sentencia o el conjunto de ellas, anteriores a un caso determinado, \u00a0que por su pertinencia y semejanza en los problemas jur\u00eddicos \u00a0resueltos, debe necesariamente considerarse por las autoridades \u00a0judiciales al momento de emitir un fallo\u00bb \u00a0(SU-053-2015). Asimismo, la doctrina ha definido c\u00f3mo el \u00a0mecanismo jurisdiccional que tiene su origen en el principio stare \u00a0decisis \u00a0o estar a lo decidido, el cual consiste en la aplicaci\u00f3n de \u00a0criterios adoptados en decisiones anteriores a casos que se presenten \u00a0en situaciones posteriores y con circunstancias similares \u00a0(T-460-2016). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De \u00a0acuerdo con la autoridad que emiti\u00f3 el pronunciamiento, el \u00a0precedente se puede clasificar en dos categor\u00edas: (i) \u00a0el horizontal, el cual hace referencia a las decisiones proferidas \u00a0por autoridades del mismo nivel jer\u00e1rquico o, incluso, por el \u00a0mismo funcionario; y (ii) \u00a0el vertical, que se refiere a las decisiones adoptadas por el \u00a0superior jer\u00e1rquico o la autoridad encargada de unificar la \u00a0jurisprudencia. El precedente horizontal tiene fuerza vinculante, \u00a0atendiendo no solo a los principios de buena fe, seguridad jur\u00eddica \u00a0y confianza leg\u00edtima, sino al derecho a la igualdad que rige \u00a0en nuestra Constituci\u00f3n. Asimismo, el precedente vertical, al \u00a0provenir de la autoridad encargada de unificar la jurisprudencia \u00a0dentro de cada una de las jurisdicciones, puede ser vinculante para \u00a0el Juez, a menos que de manera suficiente y coherente explique las \u00a0razones que motivan a apartarse de la misma. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De igual forma, el \u00a0respeto al precedente judicial de los m\u00e1ximos tribunales de \u00a0cierre guarda una estrecha relaci\u00f3n con el derecho a la \u00a0igualdad, en tanto garant\u00eda constitucional que les permite a \u00a0los ciudadanos obtener decisiones judiciales id\u00e9nticas frente \u00a0a casos semejantes. Paralelamente, el respeto de los jueces a los \u00a0precedentes sentados por las altas Cortes tiene un car\u00e1cter \u00a0ordenador y unificador, en la medida que, asegura una mayor \u00a0coherencia del sistema jur\u00eddico. Sobre el particular, la Corte \u00a0Constitucional en sentencia SU-053-2015, refiri\u00f3: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>[\u2026] \u00a0En la pr\u00e1ctica jur\u00eddica actual, las instancias de \u00a0unificaci\u00f3n de jurisprudencia son ineludibles, debido a que el \u00a0derecho es dado a los operadores jur\u00eddicos a trav\u00e9s de \u00a0normas y reglas jur\u00eddicas que no tiene contenidos sem\u00e1nticos \u00a0\u00fanicos. Por tanto, el derecho es altamente susceptible de \u00a0traer consigo ambig\u00fcedades o vac\u00edos que pueden generar \u00a0diversas interpretaciones o significados que incluso, en ocasiones \u00a0deriva de la propia ambig\u00fcedad del lenguaje. Eso genera la \u00a0necesidad de que, en primer lugar, sea el juez el que fije el alcance \u00a0de \u00e9ste en cada caso concreto y, en segundo lugar, de que haya \u00a0\u00f3rganos que permitan disciplinar esa pr\u00e1ctica jur\u00eddica \u00a0en pro de la igualdad. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De \u00a0hecho, el acatamiento del precedente es una condici\u00f3n \u00a0necesaria para la realizaci\u00f3n de un orden justo y la \u00a0efectividad de los derechos y libertades de los ciudadanos, dado que \u00a0solo a partir del cumplimiento de esa garant\u00eda podr\u00e1n \u00a0identificar aquello que el ordenamiento jur\u00eddico ordena, \u00a0proh\u00edbe o permite (C-884-2015). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Lo anterior, no \u00a0significa que los jueces no puedan apartarse de la jurisprudencia de \u00a0los \u00f3rganos jurisdiccionales de cierre, como expresi\u00f3n \u00a0de la autonom\u00eda judicial constitucional. Sin embargo, para que \u00a0ello sea v\u00e1lido es necesario el previo cumplimiento del \u00a0estricto deber de identificaci\u00f3n del precedente en la decisi\u00f3n \u00a0y de la carga argumentativa suficiente, \u00abya \u00a0que la jurisprudencia de las corporaciones judiciales de cierre no \u00a0puede ser sencillamente ignorada frente a situaciones similares a las \u00a0falladas en ella\u00bb \u00a0(SU-354-2017). Puntualmente, se requiere la observancia de dos \u00a0requisitos: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>[\u2026] \u00a0El primero, refiere al requisito de transparencia, es decir, del cual \u00a0se colige que \u201clas cargas que se imponen para apartarse de un \u00a0precedente dependen de la autoridad que la profiri\u00f3\u201d. En \u00a0efecto, el juez \u201cen su providencia hace una referencia expresa \u00a0al precedente conforme al cual sus superiores funcionales o su propio \u00a0despacho han resuelto casos an\u00e1logos, pues \u2018s\u00f3lo \u00a0puede admitirse una revisi\u00f3n de un precedente si se es \u00a0consciente de su existencia\u2019. El segundo, es decir, el \u00a0requisito de suficiencia, \u00a0tiene \u00a0que ver con que el juez debe exponer razones suficientes y v\u00e1lidas, \u00a0\u201ca la luz del ordenamiento jur\u00eddico y los supuestos \u00a0f\u00e1cticos del caso nuevo que justifiquen el cambio \u00a0jurisprudencial\u201d, es decir, que no basta con ofrecer argumentos \u00a0contrarios a la posici\u00f3n de la cual se aparta, sino que debe \u00a0demostrarse que el anterior precedente ha perdido vigencia para \u00a0resolver asuntos futuros, bien sea por el cambio normativo o por la \u00a0simple transformaci\u00f3n social (\u2026). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.2. Ahora, al \u00a0analizar la decisi\u00f3n objeto de reproche, se advierte que los \u00a0argumentos por los cuales se neg\u00f3 las pretensiones en el \u00a0tr\u00e1mite ordinario laboral se remitieron a: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(i) Al momento del \u00a0traslado al r\u00e9gimen de ahorro individual que se dio en 1998, \u00a0estaban vigentes los art\u00edculos 13 y 271 de la Ley 100 de 1993, \u00a0el art\u00edculo 97 del Decreto 663 de 1993, los art\u00edculos \u00a04, 14 y 15 del Decreto 656 de 1994. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(ii) Si bien el \u00a0art\u00edculo 271 de la Ley 100 de 1993 establece como consecuencia \u00a0la invalidaci\u00f3n del traslado de r\u00e9gimen ante el \u00a0incumplimiento del deber de informaci\u00f3n, dicha sanci\u00f3n \u00a0no es aplicable al caso concreto, en tanto que \u00ablas \u00a0sanciones aqu\u00ed previstas solo las pudo establecer el \u00a0legislador en ejercicio de sus competencias; que en aplicaci\u00f3n \u00a0del debido proceso la sanci\u00f3n debe existir de manera previa al \u00a0hecho que la origina; que en virtud del principio de legalidad no \u00a0pueden aplicarse sanciones recurriendo a la analog\u00eda, ni \u00a0remitirse a normas sancionatorias que regulan otros casos; que no \u00a0pueden aplicarse normas fraccionadamente y construirse una tercera \u00a0que favorezca el derecho del accionante, que hay norma expresa sobre \u00a0la responsabilidad que compete a las AFP por perjuicios cometidos por \u00a0la acci\u00f3n u omisi\u00f3n de sus agentes y, que las sanciones \u00a0deben ser aplicadas en la forma prevista en la Ley. (Fls. 26 y ss. \u00a0del fallo cuestionado)\u00bb. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(iii) la figura de \u00a0la ineficacia de pleno derecho es propia de los actos regulados en el \u00a0estatuto comercial, los cuales nada tienen que ver \u00abcon \u00a0el acto de afiliaci\u00f3n a un r\u00e9gimen pensional\u00bb. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(iv) la \u00a0responsabilidad debe asumirla la AFP mas no Colpensiones, porque esta \u00a0no particip\u00f3 en el acto de traslado y tal hecho le es ajeno, a \u00a0la vez que fij\u00f3: \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>* El \u00a0 \u00a0 \u00a0 \u00a0 \u00a0formulario de afiliaci\u00f3n en el que la accionante se afili\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0a Horizonte (hoy Porvenir) es de 27 de diciembre de 1996, y luego, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0se traslad\u00f3 a Protecci\u00f3n el 19 de marzo de 1998 y a \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Colmena el 29 de abril de 1999. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>* La \u00a0 \u00a0 \u00a0 \u00a0 \u00a0actora es especialista en salud ocupacional y su traslado al RAIS se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0efectu\u00f3 para apoyar a un grupo empresarial y porque les \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dec\u00edan que el ISS se iba a quebrar. \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>* Se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0traslad\u00f3 en 1996 pero solo hasta 2018 solicit\u00f3 la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0nulidad del cambio, lo que no es oportuno y acceder a ello atentar\u00eda \u00a0 \u00a0 \u00a0 \u00a0 \u00a0contra la sostenibilidad financiera del sistema. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3. \u00a0Planteamientos que, como lo valor\u00f3 el A \u00a0quo, \u00a0no se acompasan con lo se\u00f1alado en casos similares donde se \u00a0debate la ineficacia de dicho traslado en asuntos de la misma \u00a0naturaleza, entre ellos: CSJ \u00a0SL 31989, 9 sep. 2008, CSJ SL 31314, 9 sep. 2008, CSJ SL 33083, 22 \u00a0nov. 2011, CSJ SL12136-2014 y CSJ SL19447-2017, \u00a0en los cuales, la Sala de Casaci\u00f3n Laboral, decant\u00f3 la \u00a0obligatoriedad, en eventos donde se depreque la ineficacia del \u00a0traslado de r\u00e9gimen pensional, \u00a0de verificar que las \u00a0administradoras de fondos de pensiones hayan cumplido con el deber de \u00a0suministrar al afiliado informaci\u00f3n clara, cierta, \u00a0comprensible y oportuna de las caracter\u00edsticas, condiciones, \u00a0beneficios, diferencias, riesgos y consecuencias de dicha acci\u00f3n, \u00a0sin que sea oponible, simplemente, la suscripci\u00f3n de un \u00a0formato por el cual el interesado manifieste su consentimiento, ni \u00a0exigible que quien alegue el inadecuado asesoramiento lo demuestre \u00a0pues la carga probatoria la asume la entidad o, importe, si dicha \u00a0persona en caso de no haberse trasladado, ser\u00eda sujeto de un \u00a0r\u00e9gimen de transici\u00f3n o tendr\u00eda consolidado el \u00a0derecho pensional, ello en atenci\u00f3n de la transcendencia de \u00a0los derechos pensionales, donde se debe garantizar la transparencia \u00a0m\u00e1xima. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En particular, en \u00a0la sentencia CSJ \u00a0SL12136-2014, se dijo: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La \u00a0importancia de lo aqu\u00ed debatido permite que esta Sala recuerde \u00a0que el sistema general de seguridad social se implant\u00f3 con el \u00a0objetivo de procurar una mayor cobertura respecto de las distintas \u00a0contingencias y se edific\u00f3 bajo los principios de eficiencia, \u00a0universalidad, solidaridad, integralidad, unidad y participaci\u00f3n, \u00a0todo ello en aras, adem\u00e1s, de elevar la calidad de vida de los \u00a0asociados y de materializar el postulado inserto en el art\u00edculo \u00a048 de la Constituci\u00f3n Pol\u00edtica. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En \u00a0particular, en materia pensional, uno de los m\u00e1s vitales \u00a0prop\u00f3sitos fue el de canalizar la multiplicidad de reg\u00edmenes \u00a0dispersos, y fue as\u00ed que cre\u00f3 solo dos de car\u00e1cter \u00a0excluyente, el solidario de prima media con prestaci\u00f3n \u00a0definida y el de ahorro individual con solidaridad; mientras el \u00a0primero se acoge el modelo en el cual se garantiza el pago de la \u00a0pensi\u00f3n preestablecida siempre que se cumpla con la densidad \u00a0de cotizaciones y la edad, constituyendo tales aportes un fondo com\u00fan \u00a0de naturaleza p\u00fablica, en el de ahorro individual con \u00a0solidaridad se privilegia el aporte de cada afiliado, y sus \u00a0rendimientos financieros, los cuales se abonan a cuentas \u00a0individuales, y la edad para hacerse acreedor de la pensi\u00f3n \u00a0est\u00e1 sujeta a que exista un acumulado que permita obtener una \u00a0mensual superior al 110% del salario m\u00ednimo legal mensual \u00a0vigente. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Para \u00a0efectos de optar por alguno de ellos, el literal b) del art\u00edculo \u00a013 de Ley 100 de 1993 dispuso la obligatoriedad de que tal \u00a0manifestaci\u00f3n fuera libre y voluntaria, y contempl\u00f3 \u00a0como sanci\u00f3n, en caso de que ello no se concretara, una multa \u00a0hasta de 50 salarios m\u00ednimos legales mensuales vigentes, \u00a0adem\u00e1s de que \u00abla \u00a0afiliaci\u00f3n respectiva quedar\u00e1 sin efecto y podr\u00e1 \u00a0realizarse nuevamente en forma libre y espont\u00e1nea por parte \u00a0del trabajador\u00bb; \u00a0el literal e) ib\u00eddem estableci\u00f3 que \u00abuna \u00a0vez efectuada la selecci\u00f3n inicial \u2026 solo podr\u00e1n \u00a0trasladarse de r\u00e9gimen por una sola vez cada tres (3) a\u00f1os \u00a0contados a partir de la selecci\u00f3n inicial en la forma en que \u00a0se\u00f1ale el gobierno nacional\u00bb, t\u00e9rmino \u00a0que luego fue ampliado a 5 a\u00f1os, seg\u00fan la Ley 797 de \u00a02003. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por \u00a0dem\u00e1s el propio art\u00edculo 272 de dicho Estatuto de la \u00a0Seguridad Social previ\u00f3 la inaplicaci\u00f3n de \u00a0disposiciones lesivas a los asociados cuando quiera que con ellas se \u00a0menoscabara la libertad, la dignidad humana y los derechos de los \u00a0trabajadores, y advirti\u00f3 sobre la preponderancia de los \u00a0principios m\u00ednimos contenidos en el precepto 53 \u00a0constitucional. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Para \u00a0el efecto huelga recordar que el art\u00edculo 36 de la Ley 100 de \u00a01993 incorpor\u00f3 tres segmentos protegidos por la rese\u00f1ada \u00a0transici\u00f3n, todos ellos basados, de manera general, en la edad \u00a0y tiempo de servicios a su entrada en vigencia. As\u00ed dispuso \u00a0que los hombres mayores de 40 a\u00f1os de edad, las mujeres con 35 \u00a0a\u00f1os de edad, y las personas que contaran 15 a\u00f1os o m\u00e1s \u00a0de servicio se les respetar\u00edan las regulaciones anteriores, no \u00a0obstante tambi\u00e9n contempl\u00f3 que dicha protecci\u00f3n \u00a0transicional no ser\u00eda aplicable en los eventos en los que las \u00a0personas, de manera libre y voluntaria, se acogieran al r\u00e9gimen \u00a0de ahorro individual con solidaridad, caso en el cual se sujetar\u00edan \u00a0plenamente a sus reglas. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En \u00a0lo concerniente a ese aparte, la Corte Constitucional tanto en la \u00a0sentencia C-789 de 2002, como en la 1024 de 2004, condicion\u00f3 \u00a0su aplicaci\u00f3n y, bajo el desarrollo del concepto de las \u00a0expectativas leg\u00edtimas, consider\u00f3 que ellas deb\u00edan \u00a0respetarse para quienes alcanzaron por lo menos los 15 a\u00f1os de \u00a0servicio, y de esa manera habilit\u00f3 que se les respetara la \u00a0transici\u00f3n, con el condicionamiento de que retornaran al de \u00a0prima media con un ahorro que no fuera inferior al monto del aporte \u00a0legal que all\u00ed les correspond\u00eda; distinto del caso de \u00a0quienes solo tuvieran la edad establecida en el rese\u00f1ado \u00a0art\u00edculo 36 de la Ley 100 de 1993, solo que ello parte de un \u00a0supuesto evidente y es que la manifestaci\u00f3n del traslado, como \u00a0se indic\u00f3, estuviera precedida de libertad, y aunque es cierto \u00a0que reglas jur\u00eddicas generales aluden a que debe demostrarse \u00a0la afectaci\u00f3n de la voluntad para anular una actuaci\u00f3n \u00a0particular, esto no puede aplicarse de la misma manera en estos \u00a0particulares eventos en los que se discute la p\u00e9rdida del \u00a0r\u00e9gimen pensional, no solo por la entidad del derecho \u00a0discutido, sino porque el Estado es garante de la prestaci\u00f3n \u00a0del servicio p\u00fablico obligatorio, y debe dirigirlo, \u00a0controlarlo y coordinarlo, y por ello deben aplicarse las \u00a0consecuencias de que no exista una decisi\u00f3n informada \u00a0(art\u00edculos 4 y 5, Ley 100 de 1993). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Es \u00a0que cuando est\u00e1n en juego aspectos tan trascendentes como la \u00a0p\u00e9rdida de la transici\u00f3n, y de contera la imposibilidad \u00a0de acceder a la pensi\u00f3n de vejez, se requiere acudir a una \u00a0hermen\u00e9utica que se avenga a los principios que inspiran al \u00a0sistema y a los reg\u00edmenes pensionales, en los que se prev\u00e9 \u00a0el traslado libre y voluntario, e incluso a las disposiciones que en \u00a0la ley as\u00ed lo imponen. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En \u00a0efecto, es el propio Estatuto de la Seguridad Social el que concept\u00faa \u00a0que el r\u00e9gimen de ahorro individual con solidaridad, si bien \u00a0propende por \u00abla \u00a0competencia entre las diferentes entidades administradoras del sector \u00a0p\u00fablico y sector social solidario\u00bb, \u00a0se rige bajo el respeto del \u00abque \u00a0libremente escojan los afiliados\u00bb, \u00a0lo que exhibe que el legislador, si bien permiti\u00f3 que nuevos \u00a0actores econ\u00f3micos incursionaran en la administraci\u00f3n \u00a0del Sistema Pensional, no descuid\u00f3 que se honraran las \u00a0prerrogativas de los afiliados, menos si se tiene en cuenta, se \u00a0insiste, que regular\u00eda derechos constitucionalmente protegidos \u00a0como la pensi\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Bajo \u00a0el entendido de que \u00abel \u00a0sistema de seguridad social integral tiene por objeto garantizar los \u00a0derechos irrenunciables de la persona y la comunidad para obtener la \u00a0calidad de vida acorde con la dignidad humana, mediante la protecci\u00f3n \u00a0de las contingencias que la afectan\u00bb (art\u00edculo \u00a01\u00b0, Ley 100 de 1993) y que la elecci\u00f3n tanto del modelo de \u00a0prima media con prestaci\u00f3n definida, como el de ahorro \u00a0individual con solidaridad, es determinante para predicar la \u00a0aplicaci\u00f3n o no del r\u00e9gimen de transici\u00f3n, es \u00a0necesario entender, que las entidades encargadas de su direcci\u00f3n \u00a0y funcionamiento, garanticen que existi\u00f3 una decisi\u00f3n \u00a0informada, y que esta fue verdaderamente aut\u00f3noma y \u00a0consciente; ello es objetivamente verificable, en el entendido de que \u00a0el afiliado debe conocer los riesgos del traslado, pero a su vez los \u00a0beneficios que aquel le reportar\u00eda, de otro modo no puede \u00a0explicarse el cambio de un r\u00e9gimen al otro. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>A \u00a0juicio de esta Sala no podr\u00eda arg\u00fcirse que existe una \u00a0manifestaci\u00f3n libre y voluntaria cuando las personas \u00a0desconocen sobre la incidencia que aquella pueda tener frente a sus \u00a0derechos prestacionales, ni puede estimarse satisfecho tal requisito \u00a0con una simple expresi\u00f3n gen\u00e9rica; de all\u00ed que \u00a0desde el inicio haya correspondido a las Administradoras de Fondos de \u00a0Pensiones dar cuenta de que documentaron clara y suficientemente los \u00a0efectos que acarrea el cambio de r\u00e9gimen, so pena de declarar \u00a0ineficaz ese tr\u00e1nsito. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Solo \u00a0a trav\u00e9s de la demostraci\u00f3n de la existencia de la \u00a0libertad informada para el cambio de r\u00e9gimen, es que el \u00a0juzgador podr\u00eda avalar su transici\u00f3n; no se trata de \u00a0demostrar razones para verificar sobre la anulaci\u00f3n por \u00a0distintas causas f\u00e1cticas, sino de determinar si hubo eficacia \u00a0en el traslado, lo que es relevante para entrar a fijar la p\u00e9rdida \u00a0o no de la transici\u00f3n normativa. Al juzgador no le debe bastar \u00a0con advertir que existi\u00f3 un traslado al r\u00e9gimen de \u00a0ahorro individual con solidaridad, sino que es menester, para la \u00a0soluci\u00f3n, advertir que la misma es v\u00e1lida, lo cual \u00a0resulta un presupuesto obvio, m\u00e1xime cuando esta Sala ha \u00a0sostenido que el r\u00e9gimen de transici\u00f3n no es una mera \u00a0expectativa. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En \u00a0perspectiva del literal b) del art\u00edculo 13 de la Ley 100 de \u00a01993, es imperativo para el Juez que deba resolver sobre la \u00a0viabilidad o no de la aplicaci\u00f3n del r\u00e9gimen de \u00a0transici\u00f3n, ante la existencia del traslado, no simplemente \u00a0verificar los requisitos atr\u00e1s descritos, sino, adem\u00e1s \u00a0dar cuenta sobre si el mismo se realiz\u00f3 bajo los par\u00e1metros \u00a0de libertad informada. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Surge \u00a0obvio que el alcance del tr\u00e1nsito del r\u00e9gimen de prima \u00a0media al de ahorro individual con solidaridad, pudo traer para un \u00a0contingente de personas la p\u00e9rdida de la transici\u00f3n; \u00a0por las caracter\u00edsticas que el mismo supone, es necesario \u00a0determinar si tambi\u00e9n en esos eventos puede predicarse simple \u00a0y llanamente que existi\u00f3 libertad y voluntariedad para que el \u00a0mismo se efectuara. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Realizar \u00a0dicha tarea debe partir de elementos objetivos, esto es que la \u00a0libertad en la toma de una decisi\u00f3n de esa \u00edndole, solo \u00a0puede justificarse cuando est\u00e1 acompa\u00f1ada de la \u00a0informaci\u00f3n precisa, en la que se delimiten los alcances \u00a0positivos y negativos en su adopci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Una \u00a0inoportuna o insuficiente asesor\u00eda sobre los puntos del \u00a0tr\u00e1nsito de r\u00e9gimen son indicativos de que la decisi\u00f3n \u00a0no estuvo precedida de la comprensi\u00f3n suficiente, y menos del \u00a0real consentimiento para adoptarla. \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>Es \u00a0evidente que cualquier determinaci\u00f3n personal de la \u00edndole \u00a0que aqu\u00ed se discute, es eficaz, cuando existe un \u00a0consentimiento informado; en materia de seguridad social, el juez no \u00a0puede ignorar que por la trascendencia de los derechos pensionales, \u00a0la informaci\u00f3n, en este caso, del traslado de r\u00e9gimen, \u00a0debe ser de transparencia m\u00e1xima. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Para \u00a0este tipo de asuntos, se repite, tales asertos no comprenden solo los \u00a0beneficios que dispense el r\u00e9gimen al que pretende \u00a0trasladarse, que puede ser cualquiera de los dos (prima media con \u00a0prestaci\u00f3n definida o ahorro individual con solidaridad), sino \u00a0adem\u00e1s el monto de la pensi\u00f3n que en cada uno de ellos \u00a0se proyecte, la diferencia en el pago de los aportes que all\u00ed \u00a0se realizar\u00edan, las implicaciones y la conveniencia o no de la \u00a0eventual decisi\u00f3n y obviamente la declaraci\u00f3n de \u00a0aceptaci\u00f3n de esa situaci\u00f3n. Esas reglas b\u00e1sicas, \u00a0permiten en caso de controversia estimar si el traslado cumpli\u00f3 \u00a0los m\u00ednimos de transparencia, y de contera, sirven de soporte \u00a0para considerar si el r\u00e9gimen de transici\u00f3n le \u00a0continuaba o no siendo aplicable. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El \u00a0juez no puede pasar inadvertidas falencias informativas, menos \u00a0considerar que ello no es de su resorte, pues es claro que cuando \u00a0quien acude a la jurisdicci\u00f3n reclama que se le respete el \u00a0r\u00e9gimen de transici\u00f3n, indiscutiblemente, como se \u00a0anot\u00f3, surge la perentoriedad de estudiar los elementos \u00a0estructurales para que el mismo opere, es decir, debe constatar que \u00a0el traslado se produjo en t\u00e9rminos de eficacia, para luego, \u00a0determinar las consecuencias propias. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En \u00a0ese orden se clarifica con esta decisi\u00f3n que cuando lo que se \u00a0discuta sea el traslado de reg\u00edmenes, que conlleve a la \u00a0p\u00e9rdida de la transici\u00f3n, al juzgador no solo le \u00a0corresponde determinar si aquella se respeta por contar con los 15 \u00a0a\u00f1os de servicio a la entrada de vigencia de la Ley 100 de \u00a01993, esto es el 1\u00b0 de abril de 1994, sino que ser\u00e1 \u00a0menester determinar, previamente, por tratarse de un presupuesto de \u00a0eficacia, si en todo caso aquel estuvo ajustado a los principios que \u00a0gobiernan el Estatuto de Seguridad Social, y a las reglas de libertad \u00a0de escogencia del sistema, la cual estar\u00e1 sujeta a la \u00a0comprobaci\u00f3n de que existi\u00f3 una decisi\u00f3n \u00a0documentada, precedida de las explicaciones sobre los efectos del \u00a0traslado, en todas sus dimensiones legales. 9 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Lo cual, fuera \u00a0reiterado por la \u00a0Sala de Casaci\u00f3n Laboral en decisi\u00f3n CSJ SL19447-2017, \u00a0en la que, adem\u00e1s, sin dubitaci\u00f3n alguna asever\u00f3: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Es \u00a0que el propio Estatuto de Seguridad Social, desde su origen, reconoce \u00a0que, en el marco de los reg\u00edmenes pensionales de prima media y \u00a0el de ahorro individual con solidaridad, pod\u00edan presentarse \u00a0asimetr\u00edas en la informaci\u00f3n, sobre todo con estas \u00a0\u00faltimas Administradoras de Pensiones, y contempl\u00f3 para \u00a0el efecto unas consecuencias en las que, fundamentalmente, da cuenta \u00a0sobre lo trascendente de las afiliaciones a ellos para los asociados, \u00a0m\u00e1xime la incidencia que, frente al r\u00e9gimen de \u00a0transici\u00f3n ten\u00edan y en ese sentido adopta las \u00a0correcciones pertinentes, tambi\u00e9n para los empleadores. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0que es la propia ley la que sanciona, con severidad, el \u00a0incumplimiento \u00edntegro de los deberes de informaci\u00f3n \u00a0que les ata\u00f1e e incluso, para la controversia aqu\u00ed \u00a0suscitada ello era determinante, de un lado porque la simple \u00a0manifestaci\u00f3n gen\u00e9rica de aceptar las condiciones, no \u00a0era suficiente y, de otro, correspond\u00eda dar cuenta de que se \u00a0actu\u00f3 diligentemente, no solo por la propia imposici\u00f3n \u00a0que trae consigo la referida norma, sino porque en los t\u00e9rminos \u00a0del art\u00edculo 1604 del C\u00f3digo Civil, la prueba de la \u00a0diligencia y cuidado incumbe a quien debi\u00f3 emplearlo y, en \u00a0este espec\u00edfico caso ellas no se agotan solo con traer a \u00a0colaci\u00f3n los documentos suscritos, sino la evidencia de que la \u00a0asesor\u00eda brindada era suficiente para la persona, y esto no se \u00a0satisfac\u00eda \u00fanicamente con llenar los espacios vac\u00edos \u00a0de un documento, sino con la evidencia real sobre que la informaci\u00f3n \u00a0plasmada correspondiera a la realidad y atendiera las pautas para que \u00a0se adoptara una decisi\u00f3n completamente libre, en las voces del \u00a0referido art\u00edculo 13 de la Ley 100 de 1993. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Incluso \u00a0as\u00ed lo ha destacado la Sala, de tiempo atr\u00e1s, entre \u00a0otras en decisi\u00f3n CSJ SL, oct, 2008, rad 31389 en la que \u00a0explic\u00f3: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Es \u00a0una informaci\u00f3n que se ha de proporcionar con la prudencia de \u00a0quien sabe que ella tiene el valor y el alcance de orientar al \u00a0potencial afiliado o a quien ya lo est\u00e1, y que cuando se trata \u00a0de asuntos de consecuencias may\u00fasculas y vitales, como en el \u00a0sub lite, la elecci\u00f3n del r\u00e9gimen pensional, trasciende \u00a0el simple deber de informaci\u00f3n, y como emanaci\u00f3n del \u00a0mismo reglamento de la seguridad social, la administradora tiene el \u00a0deber del buen consejo, que la compromete a un ejercicio m\u00e1s \u00a0activo al proporcionar la informaci\u00f3n, de ilustraci\u00f3n \u00a0suficiente dando a conocer las diferentes alternativas, con sus \u00a0beneficios e inconvenientes, y a\u00fan a llegar, si ese fuere el \u00a0caso, a desanimar al interesado de tomar una opci\u00f3n que \u00a0claramente le perjudica. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>No \u00a0desdice la anterior conclusi\u00f3n, lo asentado en la solicitud de \u00a0vinculaci\u00f3n a la Administradora de Pensiones que aparece \u00a0firmada por el demandante, que su traslado al r\u00e9gimen de \u00a0ahorro individual se dio de manera voluntaria, que &#8220;se realiz\u00f3 \u00a0de forma libre, espont\u00e1nea y sin presiones&#8221;, pues lo que \u00a0se echa de menos es la falta de informaci\u00f3n veraz y \u00a0suficiente, de que esa decisi\u00f3n no tiene tal car\u00e1cter \u00a0si se adopta sin el pleno conocimiento de lo que ella entra\u00f1a. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>Ese \u00a0mismo compendio normativo, en su precepto 98 indica que al ser, entre \u00a0otras las AFP entidades que desarrollan actividades de inter\u00e9s \u00a0p\u00fablico, deben emplear la debida diligencia en la prestaci\u00f3n \u00a0de los servicios, y que \u00aben la celebraci\u00f3n de las \u00a0operaciones propias de su objeto dichas instituciones deber\u00e1n \u00a0abstenerse de convertir cl\u00e1usulas que por su car\u00e1cter \u00a0exorbitante puedan afectar el equilibrio del contrato o dar lugar a \u00a0un abuso de posici\u00f3n dominante\u00bb, es decir, no se trataba \u00a0\u00fanicamente de completar un formato, ni adherirse a una \u00a0cl\u00e1usula gen\u00e9rica, sino de haber tenido los elementos \u00a0de juicio suficientes para advertir la trascendencia de la decisi\u00f3n \u00a0adoptada, tanto en el cambio de prima media al de ahorro individual \u00a0con solidaridad, encontr\u00e1ndose o no la persona en transici\u00f3n, \u00a0aspecto que soslay\u00f3 el juzgador al definir la controversia, \u00a0pues hall\u00f3 suficiente una firma en un formulario, aunque lo \u00a0incorporado en \u00e9l fuese contra evidente, es decir a pesar de \u00a0la realidad patente de que la actora, para cuando lo suscribi\u00f3, \u00a0ten\u00eda un derecho consolidado y adem\u00e1s la informaci\u00f3n \u00a0dada era falaz, desde todo punto de vista, como ya se explic\u00f3. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.4. Antecedentes \u00a0jurisprudenciales que no fueron atendidos, en punto a la tesis que se \u00a0expresa por el Tribunal al desatar el recurso de apelaci\u00f3n el \u00a04 de septiembre de 2020. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.5. \u00a0En cuanto a \u00a0los argumentos sostenidos por el Tribunal -en \u00a0la no configuraci\u00f3n de un da\u00f1o, la irretroactividad de \u00a0la ley en la materia y que Colpensiones no particip\u00f3 en el \u00a0acto de traslado, as\u00ed como en que se trataba de un perjuicio \u00a0solucionable con la ley comercial- \u00a0para justificar apartarse del citado precedente jurisprudencial \u00a0que \u00a0no fue tenido en cuenta por la Corporaci\u00f3n accionada, la Sala \u00a0comparte plenamente la visi\u00f3n de la primera instancia y hace \u00a0propias sus consideraciones, en tanto concluy\u00f3: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00abAhora \u00a0bien, el deber de informaci\u00f3n a cargo de las AFP, en los \u00a0t\u00e9rminos en que le era exigible para la \u00e9poca del \u00a0traslado de la accionante -27 de diciembre de 1996-, no \u00a0necesariamente se cumple con proyecciones pensionales a futuro o con \u00a0la manifestaci\u00f3n de las ventajas del R\u00e9gimen de Ahorro \u00a0Individual con Solidaridad. Lo que exig\u00edan las normas vigentes \u00a0a esa fecha era dar a conocer \u00abla informaci\u00f3n necesaria \u00a0para lograr la mayor transparencia en las operaciones que realicen, \u00a0de suerte que les permita, a trav\u00e9s de elementos de juicio \u00a0claros y objetivos, escoger las mejores opciones del mercado\u00bb \u00a0(numeral 1.\u00b0, art\u00edculo 97 Decreto 663 de 1993) \u2013 \u00a0vigente para la citada fecha-, premisa que implica una descripci\u00f3n \u00a0de las caracter\u00edsticas, condiciones, acceso y servicios de \u00a0cada uno de los reg\u00edmenes pensionales, de modo que la afiliada \u00a0pueda conocer con exactitud la l\u00f3gica de los sistemas p\u00fablicos \u00a0y privados de pensiones; pero tambi\u00e9n la obligaci\u00f3n de \u00a0dar a conocer toda la verdad objetiva de los reg\u00edmenes, en un \u00a0lenguaje claro, simple y comprensible. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De \u00a0otro lado, es extra\u00f1o que el tribunal desviara el estudio de \u00a0la ineficacia de traslado r\u00e9gimen pensional a que Colpensiones \u00a0no particip\u00f3 en los hechos que se recriminan por falta de \u00a0informaci\u00f3n y que considerara que la figura de la ineficacia \u00a0de pleno derecho es propia de los actos regulados en el estatuto \u00a0comercial, los cuales nada tienen que ver \u00abcon el acto de \u00a0afiliaci\u00f3n a un r\u00e9gimen pensional\u00bb, pues esta \u00a0Sala \u00a0en \u00a0sentencia CSJ SL1688-2019 indic\u00f3 que la reacci\u00f3n del \u00a0ordenamiento jur\u00eddico (arts. 271 y 272 de la Ley 100 de 1993) \u00a0a la afiliaci\u00f3n desinformada es la ineficacia, o la exclusi\u00f3n \u00a0de todo efecto jur\u00eddico del acto de traslado. Por este motivo, \u00a0el examen del acto del cambio de r\u00e9gimen pensional, por \u00a0transgresi\u00f3n del deber de informaci\u00f3n, tiene que \u00a0abordarse desde la instituci\u00f3n de la ineficacia en sentido \u00a0estricto. \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>No \u00a0est\u00e1 por dem\u00e1s recordar que el respeto al precedente \u00a0judicial y el cumplimiento del deber de transparencia, implica no \u00a0solo la carga de evocar el radicado de las sentencias y hacer una \u00a0breve alusi\u00f3n a ellas; tambi\u00e9n es fundamental ser fiel \u00a0a su texto, no distorsionar o tergiversar sus enunciados, \u00a0comprenderlos en los contextos en los que se expresan y generar en \u00a0los usuarios de la administraci\u00f3n de justicia la suficiente \u00a0confianza de que las reglas jurisprudenciales fijadas por las Altas \u00a0Cortes van a ser acatadas a menos que surjan razones poderosas y \u00a0convincentes para separarse de ellas, las cuales no se advierten en \u00a0el asunto. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por \u00a0ello, le asiste raz\u00f3n a la tutelista frente a su solicitud de \u00a0amparo, pues el Tribunal Superior del Distrito Judicial de Bogot\u00e1 \u00a0cambi\u00f3 la regla jurisprudencial de esta Sala de Casaci\u00f3n \u00a0Laboral, al interpretar de una forma diferente lo reglado en la Ley \u00a0100 de 1993 en cuando a la procedencia de la ineficacia del traslado. \u00a0As\u00ed, al momento de que el juez colegiado profiri\u00f3 su \u00a0sentencia, exist\u00eda un precedente judicial consolidado desde \u00a0hace m\u00e1s de una d\u00e9cada, que, sin raz\u00f3n y \u00a0justificaci\u00f3n alguna, desatendi\u00f3, mismo que fue \u00a0recogido en la reciente sentencia CSJ SL1452-2019, como en diferentes \u00a0acciones de tutela, entre otras la CSJ STL3199-2020.\u00bb \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Entonces, si se \u00a0hubiese acogido la tesis del \u00f3rgano de cierre en materia \u00a0laboral, sin importar si la actora era o no potencial beneficiaria \u00a0del r\u00e9gimen de transici\u00f3n, ora, si ten\u00eda una \u00a0expectativa de obtener la pensi\u00f3n, la afirmaci\u00f3n de la \u00a0demandante debi\u00f3 ser desmentida por la administradora del \u00a0fondo pensional; siendo \u00e9ste el yerro que se reprueba. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En este punto, la \u00a0Sala debe ser clara que en este caso no se asume una posici\u00f3n \u00a0respecto de la procedencia de las pretensiones elevadas al interior \u00a0del proceso laboral, como quiera que se reconoce que son las \u00a0autoridades judiciales en cada caso y acorde con el tr\u00e1mite \u00a0fijado en la ley quienes deben dilucidar tal aspecto, sino que, como \u00a0se viene de explicar, la no aplicaci\u00f3n de las pautas se\u00f1aladas \u00a0pueden llevar a una decisi\u00f3n equivocada con graves \u00a0consecuencias sobre el futuro pensional de la quejosa. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Finalmente, en \u00a0punto del planteamiento relativo a que la accionante conoc\u00eda \u00a0las consecuencias del cambio de reg\u00edmenes porque ostenta la \u00a0especialidad en salud ocupacional, y el que hizo varios cambios entre \u00a0fondos administradores de pensiones, no se encuentra acreditado ni \u00a0mucho menos as\u00ed lo argument\u00f3 Colpensiones en calidad de \u00a0impugnante, que ese grado de preparaci\u00f3n acad\u00e9mica \u00a0fuera adquirido por Astrid Escobar Jurado antes de cambiarse de \u00a0reg\u00edmenes, es decir, antes de 1996, y que le hubiera servido \u00a0para comprender las consecuencias del tr\u00e1nsito, por lo que, \u00a0tal circunstancia no tiene la entidad suficiente para considerar \u00a0desatinado el amparo en sede de tutela. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>8. As\u00ed las \u00a0cosas, para la Corte, la Sala Laboral del Tribunal Superior de Bogot\u00e1 \u00a0conculc\u00f3 los derechos de la accionante, al ignorar los \u00a0precedentes vigentes de la Corte Suprema de Justicia en lo que \u00a0respecta al an\u00e1lisis del cambio de r\u00e9gimen pensional. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por las anteriores \u00a0consideraciones, se confirmar\u00e1 el fallo impugnado en cuanto \u00a0ampar\u00f3 los derechos fundamentales \u00a0al \u00a0debido proceso, acceso a la seguridad social, igualdad y acceso a la \u00a0administraci\u00f3n de justicia de Astrid \u00a0Escobar Jurado. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>* * * * * \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En raz\u00f3n de \u00a0lo expuesto, la Corte Suprema de Justicia, Sala de Casaci\u00f3n \u00a0Penal, en Sala de Decisi\u00f3n en Tutela No. 3, administrando \u00a0justicia en nombre de la Rep\u00fablica y por autoridad de la ley, \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Primero. &#8211; \u00a0CONFIRMAR \u00a0el fallo impugnado mediante el cual se ampararon los \u00a0fundamentales los \u00a0derechos fundamentales \u00a0al \u00a0debido proceso, acceso a la seguridad social, igualdad y acceso a la \u00a0administraci\u00f3n de justicia de Astrid \u00a0Escobar Jurado. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Segundo. &#8211; \u00a0NOTIFICAR \u00a0la decisi\u00f3n de conformidad con lo dispuesto por el Decreto \u00a02591 de 1991. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Tercero. &#8211; REMITIR \u00a0el \u00a0diligenciamiento a la Corte Constitucional para su eventual revisi\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>C\u00daMPLASE \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>GERSON CHAVERRA \u00a0CASTRO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DIEGO EUGENIO \u00a0CORREDOR BELTR\u00c1N \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>EYDER PATI\u00d1O \u00a0CABRERA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Martha Liliana \u00a0Triana Suarez \u00a0<\/p>\n<p>Secretaria ( e ) \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0refiere a las sentencias CSJ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0SL 31989, 9 sep. 2008, CSJ SL1452-2019, CSJ SL1688-2019, CSJ SL \u00a0 \u00a0 \u00a0 \u00a0 \u00a01689-2019 y CSJ SL4426-2019. Cfr. Folio 15 del fallo. \u00a0<\/p>\n<p>2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0La \u00a0 \u00a0 \u00a0 \u00a0 \u00a0recurrente relacion\u00f3 los siguientes: i) que el formulario de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0afiliaci\u00f3n acredita que el traslado se hizo de forma \u00a0 \u00a0 \u00a0 \u00a0 \u00a0informada; ii) que las normas que imponen el deber de informaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0surgieron con posterioridad a su afiliaci\u00f3n, siendo que no \u00a0 \u00a0 \u00a0 \u00a0 \u00a0pod\u00edan aplicarse de forma retroactiva; iii) que la actora no \u00a0 \u00a0 \u00a0 \u00a0 \u00a0detentaba la calidad de pensionada ni estaba dentro del r\u00e9gimen \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de transici\u00f3n; iv) que la carga probatoria, en casos como el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de la demandante, no le corresponde asumirla al fondo de pensiones; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0v) el que la variaci\u00f3n del monto de la pensi\u00f3n no \u00a0 \u00a0 \u00a0 \u00a0 \u00a0representa vicio en el consentimiento ni invalida el traslado; vi) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que no utiliz\u00f3 la posibilidad de retornar al r\u00e9gimen \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de prima media; vii) acerca de la prescripci\u00f3n de la acci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y de inexistencia de la obligaci\u00f3n; viii) de la buena fe con \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la que obr\u00f3 Protecci\u00f3n; etc\u00e9tera. \u00a0<\/p>\n<p>3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Acorde con este criterio, \u00e9sta Sala de tutelas se ocup\u00f3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de asuntos similares. Cfr. CSJSTP 12082-2019 y STP17447-2019. \u00a0<\/p>\n<p>4 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Ver sentencia T-259 de 2012 M.P. Luis Ernesto Vargas Silva, \u00a0<\/p>\n<p>5 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T- 411-04 M.P. Jaime Araujo Renter\u00eda, reiterada T-888-10 M.P. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Mar\u00eda Victoria Calle Correa y T-886 de 2013 M.P. Luis \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Guillermo Guerrero Toro. \u00a0<\/p>\n<p>6 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-573-97 M.P. Jorge Arango Mej\u00eda, T-329-96 M.P. Jos\u00e9 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Gregorio Hern\u00e1ndez Galindo. \u00a0<\/p>\n<p>7 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-567-98 M.P. Eduardo Cifuentes Mu\u00f1oz. \u00a0<\/p>\n<p>8 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Sentencia T-521 de 2015. M.P. Myriam \u00c1vila Rold\u00e1n (e). \u00a0<\/p>\n<p>9 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CSJ SL12136-2014 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 Produced by the free evaluation copy of TotalHTMLConverter GERSON \u00a0CHAVERRA CASTRO \u00a0 Magistrado \u00a0ponente \u00a0 \u00a0\u00a0 STP2585-2021 \u00a0 Radicaci\u00f3n \u00a0n\u00b0 114625 \u00a0 Acta \u00a0No 026 \u00a0 \u00a0\u00a0 Bogot\u00e1, \u00a0D.C., once (11) de febrero de dos mil veintiuno (2021) \u00a0 \u00a0\u00a0 ASUNTO \u00a0 \u00a0\u00a0 La Sala decide la \u00a0impugnaci\u00f3n presentada por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,33],"tags":[],"class_list":["post-54543","post","type-post","status-publish","format-standard","hentry","category-30","category-febrero"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/54543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=54543"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/54543\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=54543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=54543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=54543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}