{"id":53841,"date":"2023-10-30T22:35:42","date_gmt":"2023-10-30T22:35:42","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/10\/30\/stp2079-2021\/"},"modified":"2023-10-30T22:35:42","modified_gmt":"2023-10-30T22:35:42","slug":"stp2079-2021","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/10\/30\/stp2079-2021\/","title":{"rendered":"STP2079-2021"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>Eyder \u00a0Pati\u00f1o Cabrera \u00a0<\/p>\n<p>Magistrado \u00a0Ponente \u00a0<\/p>\n<p>STP2079-2021 \u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0n.\u00b0 \u00a0112218 \u00a0<\/p>\n<p>(Aprobado \u00a0Acta n.\u00b0 17) \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D.C., veintiocho (28) de enero de dos mil veintiuno (2021). \u00a0<\/p>\n<p>ASUNTO \u00a0<\/p>\n<p>Resolver \u00a0la \u00a0impugnaci\u00f3n formulada por Carlos \u00a0Alberto Rivera L\u00f3pez \u00a0frente \u00a0a \u00a0la \u00a0sentencia proferida el 16 de octubre de 2020 por la Sala Penal del \u00a0Tribunal Superior de Villavicencio, mediante la cual neg\u00f3 la \u00a0acci\u00f3n de tutela presentada contra el Juzgado 2\u00ba de \u00a0Ejecuci\u00f3n de Penas y Medidas de Seguridad de Acac\u00edas, \u00a0por la presunta vulneraci\u00f3n de sus derechos al debido proceso, \u00a0a la libertad, a la igualdad, a la vida y a la dignidad humana. \u00a0<\/p>\n<p>Al \u00a0tr\u00e1mite fueron vinculados el Centro de Servicios \u00a0Administrativos de los Juzgados de Ejecuci\u00f3n de Penas y \u00a0Medidas de Seguridad de Acac\u00edas y el 2\u00ba Penal del \u00a0Circuito Especializado de Bogot\u00e1, el Consorcio Fondo de \u00a0Atenci\u00f3n en Salud PPL, el USPEC, el INPEC y la C\u00e1rcel \u00a0de Villavicencio. \u00a0<\/p>\n<p>ANTECEDENTES \u00a0<\/p>\n<p>Hechos \u00a0y fundamentos de la acci\u00f3n \u00a0<\/p>\n<p>Fueron \u00a0relatados por el A \u00a0quo \u00a0de la siguiente manera: \u00a0<\/p>\n<p>[\u2026] \u00a0Carlos Alberto Rivera L\u00f3pez, a trav\u00e9s de apoderado \u00a0judicial, indic\u00f3 que el veinte (20) de enero de dos mil nueve \u00a0(2009), el Juzgado Segundo Penal del Circuito Especializado de Bogot\u00e1 \u00a0lo conden\u00f3 a la pena de veintitr\u00e9s (23) a\u00f1os y \u00a0nueve (9) meses de prisi\u00f3n por los delitos de concierto para \u00a0delinquir agravado en concurso con secuestro extorsivo agravado y \u00a0homicidio agravado. \u00a0<\/p>\n<p>Se\u00f1al\u00f3 \u00a0que, solicit\u00f3 al Juzgado Segundo de Ejecuci\u00f3n de Penas \u00a0y Medidas de Seguridad de Acac\u00edas la concesi\u00f3n de la \u00a0libertad condicional, dado que considera cumple los requisitos para \u00a0ello; empero, tal autoridad judicial neg\u00f3 dicho subrogado \u00a0penal, sin tener en cuenta el riesgo de contagio de coronavirus \u00a0(Covid-19), dado el hacinamiento en los centros de reclusi\u00f3n. \u00a0<\/p>\n<p>Por \u00a0lo anterior, solicit\u00f3 al Juez constitucional amparar sus \u00a0derechos fundamentales al debido proceso, libertad, igualdad, vida y \u00a0dignidad humana y como consecuencia, ordenar al Juzgado Segundo de \u00a0Ejecuci\u00f3n de Penas y Medidas de Seguridad de Acac\u00edas \u00a0conceder la libertad condicional. \u00a0<\/p>\n<p>LA \u00a0SENTENCIA IMPUGNADA \u00a0<\/p>\n<p>La \u00a0Sala Penal del Tribunal Superior de Villavicencio neg\u00f3 el \u00a0amparo con fundamento en los siguientes razonamientos: \u00a0<\/p>\n<p>1. \u00a0Adujo que el Juzgado 2\u00ba de Ejecuci\u00f3n de Penas y Medidas \u00a0de Seguridad de Acac\u00edas inform\u00f3 que recibi\u00f3 \u00a0solicitud de libertad condicional presentada el 11 de junio de 2019 y \u00a0en auto del 13 de junio siguiente, la neg\u00f3, en raz\u00f3n a \u00a0que aquel fue condenado por el delito de secuestro extorsivo agravado \u00a0y el art\u00edculo 26 de la Ley 1121 de 2006, proh\u00edbe la \u00a0concesi\u00f3n de subrogados penales cuando se trate de tal \u00a0conducta, entre otras. \u00a0<\/p>\n<p>Contra \u00a0tal prove\u00eddo el accionante interpuso los recursos de \u00a0reposici\u00f3n y apelaci\u00f3n, el primero resuelto por esa \u00a0c\u00e9lula judicial el 9 de julio del a\u00f1o anterior, y, el \u00a0segundo, fue resuelto por el Juzgado 2\u00ba Penal del Circuito \u00a0Especializado de Bogot\u00e1, quien, en prove\u00eddo del 29 de \u00a0agosto de 2019, confirm\u00f3 la negativa. \u00a0<\/p>\n<p>Destac\u00f3 \u00a0que las determinaciones en cita se emitieron con apego a la Ley, \u00a0adem\u00e1s, que el demandante las reprocha sin siquiera realizar \u00a0cuestionamiento alguno respecto de dichas decisiones. \u00a0<\/p>\n<p>Advirti\u00f3 \u00a0que el actor se\u00f1al\u00f3 en la solicitud de amparo que los \u00a0Juzgados accionados negaron la libertad condicional sin tener en \u00a0cuenta la emergencia sanitaria generada por el coronavirus \u00a0(covid-19), situaci\u00f3n que por supuesto no fue analizada en las \u00a0referidas decisiones, pues se emitieron el a\u00f1o anterior y no \u00a0se evidencia que aquel hubiese presentado alg\u00fan requerimiento \u00a0sobre el particular. \u00a0<\/p>\n<p>2. \u00a0Afirm\u00f3 que frente a las nuevas solicitudes de libertad \u00a0condicional del interesado, que el despacho que vigila su condena en \u00a0determinaciones del 9 de julio y 5 de diciembre de 2019, dispuso no \u00a0emitir nuevo pronunciamiento y estar a lo resuelto en prove\u00eddo \u00a0del 13 de junio de ese a\u00f1o, al considerar que las peticiones \u00a0no hac\u00edan referencia a nuevos elementos de juicio que \u00a0permitieran variar la decisi\u00f3n adoptada y que se fundamenta en \u00a0una prohibici\u00f3n legal. \u00a0<\/p>\n<p>3. \u00a0De considerar el actor que est\u00e1 privado de la libertad de \u00a0forma ilegal o que hay una prolongaci\u00f3n ilegal puede acudir a \u00a0la acci\u00f3n de habeas corpus. \u00a0<\/p>\n<p>4. \u00a0El demandante no asumi\u00f3 la carga argumentativa que le era \u00a0exigible frente al derecho a la igualdad, ni se\u00f1al\u00f3 en \u00a0qu\u00e9 caso espec\u00edfico las autoridades judiciales \u00a0accionadas obraron en forma diferente, a efecto de realizar el \u00a0correspondiente test de igualdad. Igual situaci\u00f3n ocurre \u00a0frente los derechos a la vida y a la dignidad humana, pues el actor \u00a0no especific\u00f3 en qu\u00e9 consist\u00eda dicha vulneraci\u00f3n \u00a0y tampoco, lo demostr\u00f3. \u00a0<\/p>\n<p>LA \u00a0IMPUGNACI\u00d3N \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>CONSIDERACIONES \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Problema \u00a0 \u00a0 \u00a0 \u00a0 \u00a0jur\u00eddico \u00a0<\/p>\n<p>Corresponde \u00a0a la Corte determinar si \u00a0en este caso las accionadas vulneraron los derechos al debido \u00a0proceso, a la libertad, a la igualdad, a la vida y a la dignidad \u00a0humana del interesado con ocasi\u00f3n de la negativa de conceder \u00a0su libertad condicional y al interior del centro en el cual est\u00e1 \u00a0recluido. \u00a0<\/p>\n<p>2. \u00a0La procedencia excepcional de la tutela contra providencias \u00a0judiciales \u00a0<\/p>\n<p>En \u00a0repetidas ocasiones la jurisprudencia ha reiterado que el amparo \u00a0constitucional contra providencias judiciales es no s\u00f3lo \u00a0excepcional, sino excepcional\u00edsimo. \u00a0Lo anterior para no afectar la seguridad jur\u00eddica y como \u00a0amplio respeto por la autonom\u00eda judicial garantizada en la \u00a0Carta Pol\u00edtica. \u00a0<\/p>\n<p>Al \u00a0respecto, la Corte Constitucional, en sentencia \u00a0 \u00a0 \u00a0 CC T \u2013 \u00a0780-2006, dijo: \u00a0<\/p>\n<p>La \u00a0eventual procedencia de la acci\u00f3n de tutela contra sentencias \u00a0judiciales y otras providencias que pongan fin al proceso tiene \u00a0connotaci\u00f3n de excepcional\u00edsima, \u00a0lo \u00a0cual significa que procede siempre \u00a0y cuando se cumplan unos determinados requisitos muy estrictos que la \u00a0jurisprudencia se ha encargado de especificar. \u00a0(Negrillas y subrayas fuera del original.) \u00a0<\/p>\n<p>Para \u00a0que \u00a0ello \u00a0tenga lugar se deben cumplir una serie de requisitos de \u00a0procedibilidad, unos de car\u00e1cter general, que habilitan su \u00a0interposici\u00f3n, y otros espec\u00edficos, que apuntan a la \u00a0procedencia misma del amparo1. \u00a0De manera que quien acude a \u00e9l tiene la carga no s\u00f3lo \u00a0respecto de su planteamiento, sino de su demostraci\u00f3n. \u00a0<\/p>\n<p>Dentro \u00a0de los primeros se encuentran: \u00a0<\/p>\n<p>a) \u00a0Que el asunto discutido resulte de relevancia constitucional. \u00a0<\/p>\n<p>b) \u00a0Que se hayan agotado todos los medios ordinarios y extraordinarios de \u00a0defensa judicial. \u00a0<\/p>\n<p>c) \u00a0Que se est\u00e9 ante un perjuicio iusfundamental \u00a0irremediable. \u00a0<\/p>\n<p>d) \u00a0Que se cumpla con el requisito de inmediatez, esto es, que se \u00a0interponga dentro de un t\u00e9rmino razonable y justo. \u00a0<\/p>\n<p>e) \u00a0Que se trate de una irregularidad procesal, y la misma tenga un \u00a0efecto decisivo o determinante en la decisi\u00f3n que se impugna y \u00a0que afecte los derechos fundamentales de la parte actora. \u00a0<\/p>\n<p>f) \u00a0Que se identifiquen de manera razonable los hechos que generaron la \u00a0transgresi\u00f3n y los derechos vulnerados, y, adem\u00e1s, que \u00a0esa violaci\u00f3n haya sido alegada dentro del proceso, siempre \u00a0que hubiese sido posible. \u00a0<\/p>\n<p>g) \u00a0Que no se trate de sentencias de tutela. \u00a0<\/p>\n<p>Los \u00a0segundos, por su parte, apuntan a que se demuestre que la providencia \u00a0adolece de alg\u00fan defecto org\u00e1nico, procedimental \u00a0absoluto, f\u00e1ctico, material o sustantivo, un error inducido, o \u00a0carece por completo de motivaci\u00f3n, desconoce el precedente o \u00a0viola directamente la Constituci\u00f3n. \u00a0<\/p>\n<p>2.1. \u00a0En \u00a0este caso, el Juzgado Segundo de Ejecuci\u00f3n de Penas y Medidas \u00a0de Seguridad de Acaci\u0301as en auto del 13 de junio de 2019 neg\u00f3 \u00a0la solicitud de libertad condicional requerida por el actor, en \u00a0virtud a que fue condenado por el delito de secuestro extorsivo \u00a0agravado y el arti\u0301culo 26 de la Ley 1121 de 2006, proh\u00edbe \u00a0la concesi\u00f3n de subrogados penales cuando se trate de la \u00a0mencionada conducta. \u00a0<\/p>\n<p>Contra \u00a0esa decisi\u00f3n, el accionante interpuso los recursos de \u00a0reposici\u00f3n y apelacio\u0301n, el primero fue resuelto el 9 de \u00a0julio de ese a\u00f1o en el sentido no reponer el auto. \u00a0<\/p>\n<p>El \u00a0Juzgado 2\u00ba Penal del Circuito Especializado de Bogot\u00e1 el \u00a029 de agosto de esa anualidad, la confirmo\u0301. \u00a0<\/p>\n<p>La \u00a0Corte estima que el actor agot\u00f3 los recursos ordinarios de \u00a0defensa contra la determinaci\u00f3n que le neg\u00f3 la \u00a0solicitud liberatoria, raz\u00f3n por la cual se verificar\u00e1 \u00a0si las determinaciones \u00a0reprochadas \u00a0son arbitrarias y constitutivas de causal gen\u00e9rica de \u00a0procedibilidad. \u00a0<\/p>\n<p>La \u00a0Sala anticipa que las providencias cuestionadas resultan razonables y \u00a0ajustadas a los par\u00e1metros legales y constitucionales. \u00a0<\/p>\n<p>En \u00a0efecto, los argumentos son coherentes y est\u00e1n conforme a la \u00a0normatividad que regulan el tema, los cuales les permitieron a las \u00a0autoridades accionadas negar la libertad pretendida por el actor, en \u00a0virtud de la prohibici\u00f3n existente en el art\u00edculo 26 de \u00a0la Ley 1121 de 2006, seg\u00fan las cual no es dable la concesi\u00f3n \u00a0de beneficios respecto a las personas condenadas por el delito de \u00a0concierto para delinquir agravado en concurso con secuestro extorsivo \u00a0agravado y homicidio agravado, como es el caso del demandante. \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>Por \u00a0lo anterior, es claro que la parte accionante \u00a0busca \u00a0cuestionar el raciocinio jur\u00eddico de la jurisdicci\u00f3n \u00a0penal y, con ello, protestar por el sentido de la determinaci\u00f3n \u00a0adoptada por los accionados. \u00a0<\/p>\n<p>Entendiendo, \u00a0como se debe, que la acci\u00f3n de tutela no es una herramienta \u00a0jur\u00eddica complementaria, que en este evento, se convertir\u00eda \u00a0pr\u00e1cticamente en una instancia adicional, no es adecuado \u00a0plantear por esta senda la incursi\u00f3n en causales de \u00a0procedibilidad, originadas en la supuesta arbitrariedad en la \u00a0decisi\u00f3n \u00a0contraria a los intereses del demandante. \u00a0<\/p>\n<p>Argumentos \u00a0como los presentados por el \u00a0peticionario son \u00a0incompatibles con el amparo, pues pretende revivir un debate que fue \u00a0debidamente superado en el escenario propicio para ello, y con \u00a0exclusividad ante los jueces competentes; no as\u00ed ante el juez \u00a0constitucional, porque su labor no consiste en oficiar como un \u00a0instrumento m\u00e1s de la justicia ordinaria. \u00a0<\/p>\n<p>2.2. \u00a0En atenci\u00f3n a los nuevos pedimentos liberatorios el \u00a0Juzgado 2\u00ba de Ejecuci\u00f3n de Penas y Medidas de Seguridad \u00a0de Acac\u00edas en autos del 9 de julio y 5 de diciembre de 2019, \u00a0dispuso no emitir nuevo pronunciamiento y estarse a lo resuelto en \u00a0prove\u00eddo del 13 de junio de ese a\u00f1o, al estimar que las \u00a0peticiones no hac\u00edan referencia a nuevos elementos de juicio \u00a0que permitieran variar la decisio\u0301n adoptada y que se fundamenta \u00a0en una prohibici\u00f3n legal. \u00a0<\/p>\n<p>En \u00a0ese orden, no constitu\u00eda deber legal del despacho que vigila \u00a0la condena en contra del actor emitir nuevo pronunciamiento, pues no \u00a0concurr\u00edan novedosos elementos facticos o normativos que \u00a0hicieran variar la decisi\u00f3n adoptada el 13 de junio de 2019, \u00a0la cual, estaba debidamente ejecutoriada. \u00a0<\/p>\n<p>Sobre \u00a0ese aspecto, la Corte Constitucional, en sentencia CC T-267-2017, \u00a0se\u00f1al\u00f3: \u00a0<\/p>\n<p>[\u2026] \u00a0Respecto \u00a0al derecho al acceso a la administraci\u00f3n de justicia es de \u00a0recordar que este se erige como una prerrogativa fundamental, la cual \u00a0se define como la \u00a0posibilidad que tienen las personas de acudir a las autoridades \u00a0judiciales para buscar la preservaci\u00f3n del orden jur\u00eddico \u00a0y la protecci\u00f3n o restablecimiento de sus derechos. Sin \u00a0embargo, cuando se trata de formulaci\u00f3n de peticiones ante las \u00a0autoridades judiciales que repiten cuestionamientos anteriores los \u00a0cuales han sido respondidos en forma oportuna y debida, el juez puede \u00a0remitirse a las providencias pasadas, mediante las cuales resolvi\u00f3 \u00a0lo solicitado, sin que esto constituya una denegaci\u00f3n de \u00a0justicia. \u00a0<\/p>\n<p>[\u2026] \u00a0<\/p>\n<p>Esto \u00a0lleva a concluir que no solo no se presenta una vulneraci\u00f3n al \u00a0derecho al debido proceso [\u2026], sino que tampoco se viol\u00f3 \u00a0el derecho al acceso a la administraci\u00f3n de justicia ya que \u00a0las \u00a0autoridades judiciales accionadas no est\u00e1n en la obligaci\u00f3n \u00a0de emitir un nuevo pronunciamiento en relaci\u00f3n con la \u00a0solicitud del accionante, con fundamento en que se trata de una \u00a0petici\u00f3n que repite un cuestionamiento formulado en repetidas \u00a0ocasiones, el cual ya fue objeto de pronunciamiento de fondo por \u00a0parte de las autoridades demandadas. \u00a0<\/p>\n<p>Por \u00a0tal \u00a0raz\u00f3n, \u00a0frente a las solicitudes posteriores, que con igual prop\u00f3sito \u00a0y sustento fueron elevadas por el demandante, el juzgado que vigila \u00a0su condena decidi\u00f3 estarse a lo resuelto, puesto que si bien \u00a0es cierto no existen restricciones en cuanto a las oportunidades en \u00a0las que se pueda solicitar la libertad condicional, tambi\u00e9n lo \u00a0es que esta facultad no puede presentarse de manera excesiva o \u00a0desmedida, m\u00e1xime cuando son sustentadas con an\u00e1logas \u00a0circunstancias f\u00e1cticas y legales, conforme lo expresa la \u00a0parte accionada. \u00a0<\/p>\n<p>Entonces, \u00a0ninguna duda emerge que, al no contener la solicitud nuevos elementos \u00a0que introdujeran variaci\u00f3n a la situaci\u00f3n del \u00a0sentenciado con relaci\u00f3n al beneficio reclamado, al demandado \u00a0no le quedaba opci\u00f3n diferente que abstenerse de abordar \u00a0nuevamente la tem\u00e1tica planteada, en aplicaci\u00f3n de los \u00a0principios de econom\u00eda procesal y eficiencia. Se precisa, que \u00a0en esa ocasi\u00f3n, el interesado tampoco hizo alusi\u00f3n al \u00a0Covid-19. \u00a0<\/p>\n<p>3. \u00a0Sobre los servicios de salud de las personas privadas de la libertad \u00a0<\/p>\n<p>3.1. \u00a0La Corte Constitucional, en repetidas ocasiones2, \u00a0ha se\u00f1alado la exigencia superior de \u00a0otorgar un trato digno a la poblaci\u00f3n carcelaria \u00a0pues el \u00a0Estado Social de Derecho y la multiplicidad de instrumentos \u00a0internacionales, aprobados por Colombia3, \u00a0imponen el respeto efectivo por la dignidad de la persona privada de \u00a0la libertad. Esto significa que la dignidad humana, como presupuesto \u00a0del sistema de derechos y garant\u00edas consagrados en la \u00a0Constituci\u00f3n, \u00abtiene \u00a0un valor absoluto no susceptible de ser limitado bajo ninguna \u00a0circunstancia\u00bb, \u00a0por lo que su garant\u00eda se impone a\u00fan en circunstancias \u00a0donde algunas garant\u00edas se encuentran limitadas o suspendidas. \u00a0<\/p>\n<p>En \u00a0ese entendido, se estar\u00eda bajo la \u00f3ptica de derechos \u00a0intocables, de acuerdo con la clasificaci\u00f3n que de los \u00a0derechos fundamentales de los reclusos ha realizado la Corte \u00a0Constitucional en sentencia CC T-213-2011: \u00a0<\/p>\n<p>[\u2026] \u00a0Esta \u00a0Corporaci\u00f3n ha determinado que los derechos fundamentales de \u00a0los reclusos pueden clasificarse en tres grupos:\u00a0 \u00a0(i) \u00a0los derechos intocables, \u00a0aquellos que son inherentes a la naturaleza humana y no pueden \u00a0suspenderse ni limitarse por el hecho de que su titular se encuentre \u00a0recluido. En este grupo se encuentran los derechos a la vida, la \u00a0dignidad humana, la integridad personal, la igualdad, libertad \u00a0religiosa, debido proceso y petici\u00f3n, (ii) los \u00a0derechos suspendidos, \u00a0son consecuencia l\u00f3gica y directa de la pena impuesta, tales \u00a0como: la libertad personal, la libre locomoci\u00f3n entre otros, \u00a0(iii) los \u00a0derechos restringidos, \u00a0son el resultado de la relaci\u00f3n de sujeci\u00f3n del interno \u00a0para con el Estado, dentro de \u00e9stos encontramos los derechos \u00a0al trabajo, a la educaci\u00f3n, a la intimidad personal y \u00a0familiar, de reuni\u00f3n, de asociaci\u00f3n, libre desarrollo \u00a0de la personalidad, libertad de expresi\u00f3n. En consecuencia, la \u00a0relaci\u00f3n de especial sujeci\u00f3n que existe entre las \u00a0personas que se encuentran privadas de la libertad y el Estado, no es \u00a0otra cosa que \u201cuna relaci\u00f3n jur\u00eddica donde el \u00a0predominio de una parte sobre la otra no impide la existencia de \u00a0derechos y deberes para ambas partes. \u00a0<\/p>\n<p>3.2. \u00a0En el presente asunto, lo primero que resulta necesario resaltar es \u00a0que desde el 7 \u00a0de enero de 2020 la Organizaci\u00f3n Mundial de la Salud declar\u00f3 \u00a0el virus Covid-19 como emergencia de salud p\u00fablica de \u00a0importancia internacional y el 11 de marzo siguiente lo denomin\u00f3 \u00a0como una pandemia. \u00a0<\/p>\n<p>El \u00a0primer caso en contagio en Colombia se confirm\u00f3 el 6 de marzo \u00a0del presente a\u00f1o y el 11 de ese mes y a\u00f1o el Instituto \u00a0Nacional Penitenciario [INPEC] expidi\u00f3 la Directiva n.\u00b0 \u00a0004, a trav\u00e9s de la cual socializ\u00f3 el protocolo para \u00a0prevenir las infecciones al interior de los centros de reclusi\u00f3n: \u00a0correcto lavado de manos y uso de elementos sanitarios, adecuada \u00a0manera de estornudar, de sistema de ventilaci\u00f3n y la \u00a0importancia del distanciamiento social. Asimismo, promovi\u00f3 los \u00a0mecanismos de b\u00fasqueda activa de personas con sintomatolog\u00eda \u00a0respiratoria y la ruta de acci\u00f3n ante posibles casos de \u00a0Covid-19. Adem\u00e1s, suspendi\u00f3 todas las visitas de \u00a0personal externo, restringi\u00f3 el acceso de personas \u00a0provenientes de centros transitorios de reclusi\u00f3n, las \u00a0remisiones a instalaciones judiciales, el traslado de patios, y \u00a0reforz\u00f3 el sistema de adecuado manejo de residuos, entre otras \u00a0medidas. \u00a0<\/p>\n<p>A \u00a0trav\u00e9s de la Resoluci\u00f3n No. 385 del 12 de marzo \u00a0siguiente el Ministerio de Salud y Protecci\u00f3n Social declar\u00f3 \u00a0el estado de emergencia sanitaria y mediante el Decreto 417 del 17 \u00a0marzo de esta anualidad el Gobierno proclam\u00f3 el estado de \u00a0emergencia econ\u00f3mica, social y ecol\u00f3gica a nivel \u00a0nacional. \u00a0<\/p>\n<p>El \u00a0INPEC en Resoluci\u00f3n n.\u00b0 001144 del 22 del mismo mes y a\u00f1o, \u00a0declar\u00f3 el estado de emergencia penitenciaria y carcelaria en \u00a0los establecimientos de reclusi\u00f3n del orden nacional. En la \u00a0misma fecha, el Ministerio de Salud y Protecci\u00f3n Social \u00a0expidi\u00f3 los lineamientos para el control y prevenci\u00f3n \u00a0de casos por Covid-19 en la poblaci\u00f3n privada de la libertad. \u00a0<\/p>\n<p>Mediante \u00a0Resoluci\u00f3n n.\u00b0 1274 del 25 de marzo del presente a\u00f1o, \u00a0el INPEC declar\u00f3 la urgencia manifiesta debido a la pandemia, \u00a0a los amotinamientos presentados, a las graves condiciones \u00a0sanitarias, de salud, de hacinamiento y de infraestructura, y a la \u00a0falla en la prestaci\u00f3n de servicios esenciales. \u00a0<\/p>\n<p>Al \u00a0d\u00eda siguiente, el INPEC emiti\u00f3 la Circular n.\u00b0 009 \u00a0a trav\u00e9s de la cual imparti\u00f3 instrucciones al \u00a0coordinador del grupo de derechos humanos, a los directores \u00a0regionales y de los establecimientos penitenciarios y carcelarios, en \u00a0el que indic\u00f3 que los centros de reclusi\u00f3n deben contar \u00a0en todo momento con un servidor que desempe\u00f1e las funciones \u00a0del c\u00f3nsul de derechos humanos, quien debe dedicarse de manera \u00a0exclusiva para ello y tener contacto permanente con la poblaci\u00f3n \u00a0privada de la libertad. De igual modo, en Circular n.\u00b0 010 de la \u00a0misma calenda, defini\u00f3 los lineamientos sobre alistamiento y \u00a0medidas de seguridad para el personal del cuerpo de custodia y \u00a0vigilancia del INPEC. \u00a0<\/p>\n<p>3.3. \u00a0En este caso, si bien de forma gen\u00e9rica el actor alude a la \u00a0crisis carcelaria en virtud del Covid-19, no refiri\u00f3 alguna \u00a0situaci\u00f3n especial que lo catalogue como persona en riesgo por \u00a0padecer alguna comorbilidad, tampoco expuso que su salud est\u00e9 \u00a0afectada o que alg\u00fan servicio m\u00e9dico le hubiese sido \u00a0negado o est\u00e9 pendiente de realizarse. Por el contrario los \u00a0organismos carcelarios vinculados al tr\u00e1mite expusieron de \u00a0forma detallada los protocolos que han implementado en la C\u00e1rcel \u00a0de Acac\u00edas \u00a0donde se encuentra el actor. \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>Por \u00a0las razones anotadas, se ratificar\u00e1 el fallo. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la Sala de Decisi\u00f3n de Tutelas \u00a0No. 3 de la Sala de Casaci\u00f3n Penal de la Corte Suprema de \u00a0Justicia, administrando justicia en nombre de la Rep\u00fablica y \u00a0por autoridad de la Ley, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>Primero. \u00a0Confirmar la \u00a0sentencia impugnada. \u00a0<\/p>\n<p>Segundo. \u00a0Disponer \u00a0el env\u00edo de las diligencias a la Corte Constitucional, para la \u00a0eventual revisi\u00f3n de los fallos proferidos. \u00a0<\/p>\n<p>NOTIF\u00cdQUESE \u00a0Y C\u00daMPLASE \u00a0<\/p>\n<p>Eyder \u00a0Pati\u00f1o Cabrera \u00a0<\/p>\n<p>Gerson \u00a0Chaverra Castro \u00a0<\/p>\n<p>Diego \u00a0Eugenio Corredor Beltr\u00e1n \u00a0<\/p>\n<p>Nubia \u00a0Yolanda Nova Garc\u00eda \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Fallo C-590 de 08 de junio de 2005 y T-332 de 2006. \u00a0<\/p>\n<p>2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-424 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de 1992. M.P. Fabio Mor\u00f3n D\u00edaz, T-705 de 1996. M.P. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Eduardo Cifuentes Mu\u00f1oz, T-435 de 1997. M.P. Jos\u00e9 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Gregorio Hern\u00e1ndez Galindo, T-317 de 1997. M.P. Vladimiro \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Naranjo Mesa. \u00a0<\/p>\n<p>3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Art\u00edculo \u00a0 \u00a0 \u00a0 \u00a0 \u00a010 del\u00a0Pacto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Internacional de Derechos Civiles y Pol\u00edticos, art\u00edculo \u00a0 \u00a0 \u00a0 \u00a0 \u00a05\u00ba del Pacto de San Jos\u00e9 de Costa Rica y Reglas m\u00ednimas \u00a0 \u00a0 \u00a0 \u00a0 \u00a0para el tratamiento de los reclusos y procedimientos para la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0aplicaci\u00f3n efectiva de las reglas. Naciones Unidas. 1955, \u00a0 \u00a0 \u00a0 \u00a0 \u00a01984, 1989, 1990. Resoluciones 34\/169 de 1979, 43\/73 de 1988 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Asamblea General de Naciones Unidas. \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 Produced by the free evaluation copy of TotalHTMLConverter Eyder \u00a0Pati\u00f1o Cabrera \u00a0 Magistrado \u00a0Ponente \u00a0 STP2079-2021 \u00a0 Radicaci\u00f3n \u00a0n.\u00b0 \u00a0112218 \u00a0 (Aprobado \u00a0Acta n.\u00b0 17) \u00a0 Bogot\u00e1, \u00a0D.C., veintiocho (28) de enero de dos mil veintiuno (2021). \u00a0 ASUNTO \u00a0 Resolver \u00a0la \u00a0impugnaci\u00f3n formulada por Carlos \u00a0Alberto Rivera L\u00f3pez \u00a0frente \u00a0a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,32],"tags":[],"class_list":["post-53841","post","type-post","status-publish","format-standard","hentry","category-30","category-enero"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/53841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=53841"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/53841\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=53841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=53841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=53841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}