{"id":50742,"date":"2023-09-15T20:50:16","date_gmt":"2023-09-15T20:50:16","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/15\/atp742-2020\/"},"modified":"2023-09-15T20:50:16","modified_gmt":"2023-09-15T20:50:16","slug":"atp742-2020","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/15\/atp742-2020\/","title":{"rendered":"ATP742-2020"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>FABIO \u00a0OSPITIA GARZ\u00d3N \u00a0<\/p>\n<p>Magistrado \u00a0Ponente \u00a0<\/p>\n<p>ATP742 \u00a0&#8211; 2020 \u00a0<\/p>\n<p>Impedimento \u00a0en tutela No. 1442\/111410 \u00a0<\/p>\n<p>Acta \u00a0n\u00b0 141 \u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D. C., siete (07) de julio de dos mil veinte (2020). \u00a0<\/p>\n<p>ASUNTO \u00a0<\/p>\n<p>La \u00a0Sala se pronuncia sobre el impedimento manifestado por el Magistrados \u00a0EDGAR MANUEL CAICEDO HERRERA, JUAN CARLOS CONDE SERRANO y LUIS \u00a0GUIOVANNI S\u00c1NCHEZ C\u00d3RDOBA, integrantes de la Sala Penal \u00a0del Tribunal Superior de C\u00facuta, para conocer de la demanda de \u00a0tutela presentada por FANNY MART\u00cdNEZ VILA, contra la Fiscal\u00eda \u00a0General de la Naci\u00f3n (Seccional Norte de Santander), la \u00a0Direcci\u00f3n Ejecutiva y la Secci\u00f3n de N\u00f3mina, \u00a0Subdirecci\u00f3n Regional de Apoyo a la Gesti\u00f3n de la misma \u00a0entidad. \u00a0<\/p>\n<p>ACTUACI\u00d3N \u00a0JUR\u00cdDICA RELEVANTE \u00a0<\/p>\n<p>1. \u00a0FANNY MART\u00cdNEZ VILA, quien se desempe\u00f1a como Fiscal \u00a0Delegado ante los Juzgados Penales del Circuito de Los Patios (Norte \u00a0de Santander), \u00a0promovi\u00f3 \u00a0acci\u00f3n de tutela contra las aludidas entidades, para que se \u00a0aplicara la excepci\u00f3n de inconstitucionalidad del Decreto \u00a0Legislativo No. 568 \u00a0de 2020, que ordena la deducci\u00f3n de un impuesto solidario, \u00a0creado con ocasi\u00f3n de la emergencia sanitaria \u00a0decretada por causa del virus Covid-19. \u00a0<\/p>\n<p>Sostuvo \u00a0que el descuento a su salario afecta su congrua subsistencia y la de \u00a0su hijo, quien depende econ\u00f3micamente de ella. Adem\u00e1s, \u00a0la posibilidad de cumplir con sus obligaciones financieras, lo que \u00a0vulnera su m\u00ednimo vital, pues el ingreso que recibe, \u00a0efectuando las respectivas deducciones, no le alcanza para cubrir el \u00a0total de sus necesidades b\u00e1sicas. \u00a0<\/p>\n<p>2. \u00a0Tras haber asumido el conocimiento de la actuaci\u00f3n, por auto \u00a0del 11 de junio de 2020, los Magistrados de la Sala Penal del \u00a0Tribunal de C\u00facuta, manifestaron encontrarse incursos en la \u00a0causal de impedimento se\u00f1alada en el numeral 1\u00ba del \u00a0art\u00edculo 56 de la Ley 906 de 2004. \u00a0<\/p>\n<p>Adujeron \u00a0que la \u00a0actuaci\u00f3n censurada por parte de la accionante, compromete la \u00a0ponderaci\u00f3n e imparcialidad para definir el asunto, ya que \u00a0como servidores p\u00fablicos tambi\u00e9n les asiste un inter\u00e9s \u00a0en el problema jur\u00eddico planteado, porque se les ha venido \u00a0aplicando el descuento establecido en el Decreto Legislativo 568 de \u00a02020, ante la emergencia econ\u00f3mica, social y ecol\u00f3gica \u00a0que vive el pa\u00eds por causa del Covid-19. \u00a0<\/p>\n<p>Por \u00a0tanto, al tener un inter\u00e9s directo en el resultado de la \u00a0acci\u00f3n constitucional, se apartaron de su conocimiento. \u00a0<\/p>\n<p>3. \u00a0Con prove\u00eddo del 23 de junio \u00faltimo, los conjueces JOS\u00c9 \u00a0MAR\u00cdA PEL\u00c1EZ MEJ\u00cdA, JUVENAL BERNAL BENCARDINO y \u00a0V\u00cdCTOR MANUEL S\u00c1NCHEZ LE\u00d3N, resolvieron no \u00a0aceptar el impedimento manifestado y \u00a0ordenaron remitir las diligencias a esta Corporaci\u00f3n para su \u00a0definici\u00f3n. \u00a0<\/p>\n<p>Lo \u00a0anterior, por cuanto estimaron que la peticionaria \u00a0no est\u00e1 realizando un cuestionamiento general acerca de la \u00a0constitucionalidad del impuesto, que implique de los funcionarios un \u00a0razonamiento dirigido a determinar la compatibilidad del impuesto con \u00a0los postulados de la Carta Pol\u00edtica y que apunte a la creaci\u00f3n \u00a0de una regla o ratio \u00a0universalizable \u00a0para todos los funcionarios judiciales del pa\u00eds. \u00a0<\/p>\n<p>Por \u00a0el contrario, expresaron, el amparo se fundamenta en particulares \u00a0condiciones econ\u00f3micas de su modus \u00a0vivendi, \u00a0lo \u00a0que implica estudiar hechos absolutamente espec\u00edficos de la \u00a0actora. \u00a0<\/p>\n<p>Adicionalmente, consideraron que la decisi\u00f3n que se tome en la \u00a0tutela no los cobijar\u00eda, ni representar\u00eda alg\u00fan \u00a0provecho para sus intereses, puesto que los efectos del fallo son \u00a0interpartes. Por tanto, no encontraron fundamento \u00a0razonable para considerar que los magistrados tengan un \u201cinter\u00e9s\u201d \u00a0que pueda nublar su juicio a la hora de decidir el caso, pues su \u00a0definici\u00f3n \u00fanicamente afectar\u00e1 o beneficiar\u00e1 \u00a0a la accionante. \u00a0<\/p>\n<p>CONSIDERACIONES \u00a0<\/p>\n<p>Competencia \u00a0<\/p>\n<p>De \u00a0conformidad con lo previsto en el art\u00edculo 58 A de la Ley 906 \u00a0de 2004, aplicable por remisi\u00f3n del inciso 1\u00ba del \u00a0art\u00edculo 4\u00ba del Decreto 306 de 1992, esta Sala es \u00a0competente para pronunciarse sobre la manifestaci\u00f3n de \u00a0impedimento expresada por los Magistrados de la Sala Penal del \u00a0Tribunal Superior de C\u00facuta. \u00a0<\/p>\n<p>An\u00e1lisis \u00a0del caso \u00a0<\/p>\n<p>1. \u00a0El instituto de los impedimentos y recusaciones tiene por objeto \u00a0garantizar el derecho que le asiste a todas las personas a ser \u00a0juzgadas por un juez imparcial, en desarrollo de lo dispuesto en el \u00a0art\u00edculo 5\u00b0 del C\u00f3digo de la Ley 906 de 2004 y los \u00a0art\u00edculos 10 de la Declaraci\u00f3n Universal de los \u00a0Derechos del Hombre de 1948, 14.1 del Pacto Internacional de Derechos \u00a0Civiles y Pol\u00edticos de 1966, y 8.1 de la Convenci\u00f3n \u00a0Americana Sobre Derechos Humanos de 1968. \u00a0<\/p>\n<p>2. \u00a0La causal en virtud de la cual se invoc\u00f3 el impedimento en \u00a0examen, se encuentra prevista en el numeral 1\u00b0 del art\u00edculo \u00a056 de la Ley 906 de 2004, as\u00ed: \u00a0<\/p>\n<p>\u201c1. \u00a0Que el funcionario \u00a0judicial, \u00a0su c\u00f3nyuge o compa\u00f1ero o compa\u00f1era permanente, o \u00a0alg\u00fan pariente suyo dentro del cuarto grado de consanguinidad \u00a0o civil, o segundo de afinidad, tenga \u00a0inter\u00e9s en la actuaci\u00f3n procesal. \u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>Respecto \u00a0de ella, esta Corporaci\u00f3n ha hecho \u00e9nfasis en la \u00a0necesidad de que el funcionario que se declara impedido acredite con \u00a0suficiencia, el inter\u00e9s directo o indirecto que \u00a0espec\u00edficamente concurre, capaz de perturbar su imparcialidad \u00a0u objetividad (AP2887-2019. Rad. 54.271): \u00a0<\/p>\n<p>\u201cPara \u00a0efecto de su resoluci\u00f3n esta Sala, tal como ha sido opini\u00f3n \u00a0de la Corporaci\u00f3n, ha de precisar \u00a0que ese inter\u00e9s en \u00a0la actuaci\u00f3n procesal debe entenderse como: \u201c aquella \u00a0expectativa manifiesta por la posible utilidad o menoscabo, no solo \u00a0de \u00edndole patrimonial sino tambi\u00e9n intelectual o moral, \u00a0que la soluci\u00f3n del asunto en una forma determinada acarrear\u00eda \u00a0al funcionario judicial o a sus parientes cercanos, y que, por \u00a0aparecer respaldada en serios elementos de juicio, compromete la \u00a0ponderaci\u00f3n, e imparcialidad del juzgador, tornando imperiosa \u00a0su separaci\u00f3n del proceso\u201d \u00a0(CSJ, Auto 6 de marzo de \u00a02009 Radicado 23454).\u201d1 \u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>\u201cEs \u00a0necesario, entonces, que se acredite, con suficiencia, el inter\u00e9s \u00a0directo o indirecto que concurre en el funcionario, en el \u00a0consangu\u00edneo o en la pareja, capaz de perturbar la \u00a0imparcialidad u objetividad del llamado a resolver el asunto sometido \u00a0a su consideraci\u00f3n. \u00a0<\/p>\n<p>As\u00ed \u00a0las cosas, corresponde demostrar, a trav\u00e9s de los elementos \u00a0cognoscitivos que resulten indispensables, los siguientes \u00a0presupuestos (CSJ AP, 13 ago. 2003, rad. 21.225; CSJ AP, 25 feb. \u00a02004, rad. 22.016, CSJ AP, 11 oct. 2013, rad. 41.743): \u00a0<\/p>\n<p>i) \u00a0La existencia de una expectativa tangible, en orden a obtener un \u00a0provecho de la decisi\u00f3n a adoptar en el proceso. \u00a0<\/p>\n<p>ii) \u00a0La ventaja o utilidad, debe recaer en el funcionario judicial, su \u00a0c\u00f3nyuge o compa\u00f1ero o compa\u00f1era permanente, o \u00a0alg\u00fan pariente suyo dentro del cuarto grado de consanguinidad \u00a0o civil, o segundo de afinidad. \u00a0<\/p>\n<p>iii) \u00a0El beneficio particular \u2013no general- ha de ser de naturaleza \u00a0patrimonial, intelectual o moral. \u00a0<\/p>\n<p>iv) \u00a0En el inter\u00e9s subjetivo y parcializado del funcionario deben \u00a0concurrir las caracter\u00edsticas de actualidad, pertinencia, \u00a0concreci\u00f3n, certidumbre y trascendencia.\u201d \u00a0<\/p>\n<p>En \u00a0el caso objeto de estudio, los magistrados impedidos, aseguraron \u00a0estar inmersos en la causal se\u00f1alada, debido a que tambi\u00e9n \u00a0son sujetos del impuesto solidario por \u00a0Covid-19 regulado en el Decreto 568 de 2020, cuya \u00a0inaplicaci\u00f3n la accionante solicita en la demanda de tutela, \u00a0lo que, por contera, los sit\u00faa en una circunstancia similar a \u00a0la alegada, en la que evidentemente tienen inter\u00e9s, que afecta \u00a0su imparcialidad. \u00a0<\/p>\n<p>Esta \u00a0Sala de Decisi\u00f3n, frente a un caso similar, consider\u00f3 \u00a0que los motivos expresadas por los magistrados impedidos, no \u00a0resultaban suficientes para concluir que su imparcialidad, integridad \u00a0y objetividad judicial, pudieran verse afectadas para conocer y \u00a0decidir la acci\u00f3n de tutela, entre otras razones, porque la \u00a0decisi\u00f3n a adoptar, por tener en principio efectos \u00a0interpartes, no ten\u00eda la virtualidad de favorecerlos ni \u00a0afectarlos (Radicado No. 944, providencia del 9 de junio de 2020). Al \u00a0respecto se dijo: \u00a0<\/p>\n<p>\u201cEn \u00a0primer lugar, como bien lo se\u00f1alaron los dem\u00e1s \u00a0magistrados integrantes de la Sala Penal del Tribunal, no se \u00a0evidencia que la determinaci\u00f3n que deba adoptarse en la tutela \u00a0pueda beneficiarlos directamente o a \u00absu c\u00f3nyuge o \u00a0compa\u00f1ero o compa\u00f1era permanente, o alg\u00fan \u00a0pariente suyo dentro del cuarto grado de consanguinidad o civil\u00bb, \u00a0pues se insiste, los efectos del fallo cobijar\u00edan \u00a0exclusivamente a los extremos procesales dentro de la tutela y por \u00a0tanto no podr\u00edan verse beneficiados o perjudicados con el \u00a0mismo. \u00a0<\/p>\n<p>Por \u00a0otro lado, quienes se declararon impedidos tampoco refirieron \u00a0elementos de juicio que permitieran suponer que se encontraban en la \u00a0misma situaci\u00f3n f\u00e1ctica y econ\u00f3mica que el \u00a0actor, o que obtendr\u00edan determinado provecho, utilidad o un \u00a0beneficio actual e inmediato para s\u00ed con la decisi\u00f3n, \u00a0por el contrario, cualquier determinaci\u00f3n que merezca la \u00a0tutela de G\u00d3MEZ CELIS no tendr\u00eda la entidad suficiente \u00a0para trascender a su esfera individual y favorecerlos, pues es \u00a0innegable que en cada caso el juez deber\u00e1 valorar las \u00a0circunstancias particulares que lo rodearon y con fundamento en ellas \u00a0adoptar su decisi\u00f3n. \u00a0<\/p>\n<p>As\u00ed \u00a0las cosas, acreditado entonces que la exteriorizaci\u00f3n del \u00a0impedimento correspondi\u00f3 al planteamiento de una hip\u00f3tesis \u00a0incierta y no demostrada, concluye esta Sala que tal postulaci\u00f3n \u00a0no tiene la capacidad de viciar el discernimiento e imparcialidad de \u00a0los juzgadores\u201d. \u00a0<\/p>\n<p>Esta \u00a0motivaci\u00f3n resulta aplicable al caso concreto, toda vez que \u00a0los funcionarios judiciales que se declaran impedidos no acreditaron \u00a0con suficiencia el inter\u00e9s que les asiste en la resoluci\u00f3n \u00a0de la acci\u00f3n de tutela promovida, \u00a0pues no probaron encontrarse en situaci\u00f3n id\u00e9ntica a la \u00a0accionante, y si bien es cierto el impuesto solidario les resulta \u00a0aplicable, esto no implica compromiso de su imparcialidad, porque el \u00a0an\u00e1lisis que se impone realizar deber ser a nivel individual, \u00a0frente a las particularidades de cada caso. \u00a0<\/p>\n<p>En \u00a0resumen, los magistrados no demostraron que la decisi\u00f3n que \u00a0deben adoptar les reporte directamente un provecho patrimonial, \u00a0intelectual o moral, por las razones que se dejaron expuesta, \u00a0incumpli\u00e9ndose de esta manera las exigencias de pertinencia, \u00a0concreci\u00f3n, certidumbre y trascendencia que deben acompa\u00f1ar \u00a0el inter\u00e9s alegado. \u00a0<\/p>\n<p>As\u00ed \u00a0las cosas, la manifestaci\u00f3n de impedimento no prospera. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la Corte Suprema De Justicia, Sala De \u00a0Casaci\u00f3n Penal, Sala De Decisi\u00f3n De Tutelas N\u00b0 2, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>1. \u00a0Declarar infundado \u00a0el impedimento manifestado por los Magistrados EDGAR MANUEL CAICEDO \u00a0HERRERA, JUAN CARLOS CONDE SERRANO y LUIS GUIOVANNI S\u00c1NCHEZ \u00a0C\u00d3RDOBA, integrantes de la Sala Penal del Tribunal Superior de \u00a0C\u00facuta, de \u00a0conformidad con lo expuesto en la parte motiva de esta providencia. \u00a0<\/p>\n<p>2. \u00a0Devolver \u00a0de inmediato el expediente al Tribunal de origen. \u00a0<\/p>\n<p>3. \u00a0Contra \u00a0esta determinaci\u00f3n no procede recurso alguno. \u00a0<\/p>\n<p>C\u00famplase \u00a0<\/p>\n<p>FABIO \u00a0OSPITIA GARZ\u00d3N \u00a0<\/p>\n<p>LUIS \u00a0ANTONIO HERN\u00c1NDEZ BARBOSA \u00a0<\/p>\n<p>HUGO \u00a0QUINTERO BERNATE \u00a0<\/p>\n<p>NUBIA \u00a0YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1CSJ. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0AP3008-2019. Radicaci\u00f3n n.\u00b0 55388. C.P Diego Eugenio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Corredor Beltr\u00e1n. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 FABIO \u00a0OSPITIA GARZ\u00d3N \u00a0 Magistrado \u00a0Ponente \u00a0 ATP742 \u00a0&#8211; 2020 \u00a0 Impedimento \u00a0en tutela No. 1442\/111410 \u00a0 Acta \u00a0n\u00b0 141 \u00a0 Bogot\u00e1 \u00a0D. C., siete (07) de julio de dos mil veinte (2020). \u00a0 ASUNTO \u00a0 La \u00a0Sala se pronuncia sobre el impedimento manifestado por el Magistrados \u00a0EDGAR MANUEL CAICEDO HERRERA, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-50742","post","type-post","status-publish","format-standard","hentry","category-29"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/50742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=50742"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/50742\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=50742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=50742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=50742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}