{"id":50229,"date":"2023-09-15T20:50:00","date_gmt":"2023-09-15T20:50:00","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/15\/ap1888-202054143\/"},"modified":"2023-09-15T20:50:00","modified_gmt":"2023-09-15T20:50:00","slug":"ap1888-202054143","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/15\/ap1888-202054143\/","title":{"rendered":"AP1888-2020(54143)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>EUGENIO \u00a0FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>Magistrado \u00a0ponente \u00a0<\/p>\n<p>AP1888-2020 \u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0N\u00ba 54143 \u00a0<\/p>\n<p>Acta\u00a0166\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Bogot\u00e1,\u00a0D.\u00a0C.,\u00a0doce \u00a0(12) de agosto\u00a0de dos mil veinte (2020).\u00a0 \u00a0<\/p>\n<p>Decide \u00a0la Sala la admisibilidad de los fundamentos l\u00f3gicos y de \u00a0adecuada argumentaci\u00f3n de la demanda de casaci\u00f3n \u00a0presentada por el defensor de GERARDO SINISTERRA MAZUERA contra la \u00a0sentencia de 8 de mayo de 2018, por medio de la cual el Tribunal \u00a0Superior de Cali confirm\u00f3 la proferida por el Juzgado Primero \u00a0Penal del Circuito Especializado de la misma ciudad, que lo conden\u00f3, \u00a0en calidad de determinador, del delito de secuestro extorsivo \u00a0agravado en concurso homog\u00e9neo y sucesivo. \u00a0<\/p>\n<p>HECHOS \u00a0Y ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>Hacia \u00a0las 5 de la tarde del 4 de mayo de 2012, cuando Luis Gonzalo Ram\u00edrez \u00a0Hern\u00e1ndez, \u00c1lvaro Castrill\u00f3n L\u00f3pez y otra \u00a0persona conocida solo como \u201cFelipe\u201d \u00a0se dirig\u00edan hacia el sur de Cali a bordo del autom\u00f3vil \u00a0de placas CMG-120 \u2014, con el fin de celebrar un negocio que \u00e9ste \u00a0\u00faltimo le hab\u00eda propuesto a Ram\u00edrez Hern\u00e1ndez\u2014, \u00a0a la altura de la carrera 23 con autopista suroriental, fueron \u00a0interceptados por otro automotor del cual descendieron dos sujetos \u00a0que mediante armas de fuego los condujeron a un apartamento ubicado \u00a0en la calle 9\u00aa con carrera 35 de esa ciudad, donde antiguamente \u00a0funcionaba la discoteca \u201cManisero\u201d. \u00a0<\/p>\n<p>Al \u00a0llegar a dicho lugar, \u201cFelipe\u201d \u00a0abri\u00f3 la puerta y al alrededor de 10 hombres armados que se \u00a0encontraban all\u00ed esposaron a Luis Gonzalo Ram\u00edrez \u00a0Hern\u00e1ndez y a \u00c1lvaro Castrill\u00f3n, los tiraron al \u00a0suelo y les quitaron sus pertenencias, luego de lo cual le exigieron \u00a0al primero la suma de $400.000.000,oo por su libertad, en \u00a0tanto que al segundo le pidieron $4.000.000,oo. \u00a0<\/p>\n<p>Al \u00a0d\u00eda siguiente, Ram\u00edrez Hern\u00e1ndez fue sometido a \u00a0torturas cuando sus captores utilizaron unas pinzas para halarle las \u00a0orejas y las tetillas, adem\u00e1s, le quemaron el rostro con un \u00a0cigarrillo y lo amenazaron con cortarle un dedo si no les entregaba \u00a0las escrituras p\u00fablicas y documentos de los bienes que tuviera \u00a0a su nombre. Ese mismo d\u00eda se hizo presente en el lugar \u00a0GERARDO \u00a0SINISTERRA MAZUERA, quien le manifest\u00f3 a aqu\u00e9l que \u00a0deb\u00eda pagar por lo que le hab\u00eda hecho, \u2014se \u00a0estableci\u00f3 que a\u00f1os atr\u00e1s ambos se hab\u00edan \u00a0conocido mientras estuvieron privados \u00a0de la libertad en Estados Unidos por el delito de narcotr\u00e1fico\u2014. \u00a0<\/p>\n<p>Los \u00a0familiares de Ram\u00edrez Hern\u00e1ndez y Castrill\u00f3n al \u00a0recibir llamadas telef\u00f3nicas extorsivas dieron aviso a las \u00a0autoridades y tras el operativo dispuesto se logr\u00f3 el mismo 5 \u00a0de mayo de 2012 capturar a dos sujetos1 \u00a0cuando recib\u00edan de la hija de \u00c1lvaro Castrill\u00f3n \u00a0la suma de $4.000.000,oo, luego de ello, hacia las 8 de la noche, las \u00a0v\u00edctimas fueron liberadas por sus captores. \u00a0<\/p>\n<p>El \u00a06 de mayo de 2012, el carro de placas CMG-120 fue encontrado \u00a0abandonado e incinerado en la ciudadela Poblado Campestre de Cali. \u00a0<\/p>\n<p>El \u00a0Juzgado Veintis\u00e9is Penal Municipal de Control de Garant\u00edas \u00a0de Cali libr\u00f3 orden de captura en contra de GERARDO \u00a0SINISTERRA MAZUERA, siendo capturado el 7 de febrero de 2015 en \u00a0Barranquilla, por ello, el 8 \u00a0y 9 del mismo mes y anualidad se cumpli\u00f3 en el Juzgado Trece \u00a0Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de \u00a0\u00e9sta \u00faltima ciudad la diligencia de legalizaci\u00f3n \u00a0de captura, acto en el cual tambi\u00e9n la Fiscal\u00eda le \u00a0formul\u00f3 imputaci\u00f3n como probable coautor de los \u00a0il\u00edcitos de secuestro extorsivo agravado en concurso homog\u00e9neo \u00a0y sucesivo, hurto calificado y \u00a0fabricaci\u00f3n, tr\u00e1fico, porte o tenencia de armas de \u00a0fuego, accesorios, partes o municiones agravado, \u00a0de conformidad con los art\u00edculos 169, 170, numerales 2\u00ba, \u00a06\u00ba, 8\u00ba y 10\u00ba; 239; 240, numeral 2\u00ba; y 365, \u00a0numeral 5\u00ba del C\u00f3digo Penal, con la circunstancia de \u00a0mayor punibilidad establecida en el numeral 10\u00ba del art\u00edculo \u00a058 del mismo estatuto. El imputado no acept\u00f3 los cargos y ante \u00a0el pedido elevado por el ente investigador, fue \u00a0afectado con medida de aseguramiento privativa de la libertad en \u00a0establecimiento carcelario. \u00a0<\/p>\n<p>Presentado \u00a0el escrito de acusaci\u00f3n por los mismos il\u00edcitos, en el \u00a0Juzgado \u00a0Primero Penal del Circuito Especializado de Cali \u00a0se surti\u00f3 el 26 de agosto de 2015 la respectiva audiencia de \u00a0formulaci\u00f3n, en tal acto el fiscal precis\u00f3 que acusaba \u00a0a SINISTERRA MAZUERA en calidad de coautor de los delitos de hurto \u00a0calificado y secuestro extorsivo agravado en concurso homog\u00e9neo \u00a0y sucesivo (por dos eventos: secuestro de Luis Gonzalo Ram\u00edrez \u00a0Hern\u00e1ndez y \u00c1lvaro Castrill\u00f3n L\u00f3pez), con \u00a0la circunstancia de atenuaci\u00f3n punitiva de que trata el \u00a0art\u00edculo 171 del C\u00f3digo Penal. Respecto del punible de \u00a0porte \u00a0de armas de fuego aclar\u00f3 que el grado de participaci\u00f3n \u00a0era a t\u00edtulo de autor, y retir\u00f3 la causal de agravaci\u00f3n \u00a0del numeral 5\u00ba del art\u00edculo 365 imputada para ese \u00a0il\u00edcito. \u00a0<\/p>\n<p>Celebradas \u00a0en ese despacho judicial las audiencias preparatoria de juicio oral, \u00a0en \u00e9sta \u00faltima el fiscal, al considerar que la \u00a0liberaci\u00f3n de las v\u00edctimas no obedeci\u00f3 a la \u00a0voluntad de sus captores y que estos hab\u00edan obtenido una parte \u00a0del dinero exigido, margin\u00f3 la circunstancia de atenuaci\u00f3n \u00a0punitiva que hab\u00eda sido predicada para el punible contra la \u00a0libertad individual contemplada en el art\u00edculo 171 del C\u00f3digo \u00a0Penal. \u00a0<\/p>\n<p>Finalmente, \u00a0el 17 de noviembre de 2016 fue condenado el procesado como \u00a0determinador del delito de secuestro extorsivo agravado en concurso \u00a0homog\u00e9neo y sucesivo, seg\u00fan los art\u00edculos \u00a0169 y 170, numerales 6\u00ba y 10\u00ba del C\u00f3digo Penal, sin \u00a0la causal especial de atenuaci\u00f3n, ni la circunstancia de mayor \u00a0punibilidad endilgada, a la pena principal de treinta y ochos (38) \u00a0a\u00f1os y cuatro (4) meses de prisi\u00f3n, multa en el \u00a0equivalente a 6.846,66 salarios m\u00ednimos legales mensuales \u00a0vigentes, as\u00ed y como a la accesoria de inhabilitaci\u00f3n \u00a0para el ejercicio de derechos y funciones p\u00fablicas por el \u00a0t\u00e9rmino de veinte (20) a\u00f1os, \u00a0sin concederle la \u00a0suspensi\u00f3n condicional de la ejecuci\u00f3n de la pena o la \u00a0prisi\u00f3n domiciliaria. \u00a0<\/p>\n<p>En \u00a0la misma decisi\u00f3n fue absuelto de los il\u00edcitos de porte \u00a0ilegal de armas en aplicaci\u00f3n del principio de resoluci\u00f3n \u00a0de duda, as\u00ed como del punible de hurto \u00a0calificado, ya que la fiscal\u00eda no solicit\u00f3 condena por \u00a0el mismo. \u00a0<\/p>\n<p>Impugnada \u00a0la sentencia por parte del defensor, el Tribunal Superior de Cali \u00a0mediante providencia de 8 de mayo de 2018 la confirm\u00f3 \u00a0\u00edntegramente, raz\u00f3n por la cual el profesional insisti\u00f3 \u00a0a trav\u00e9s del recurso de casaci\u00f3n allegando la respetiva \u00a0demanda, de cuya admisibilidad se pronuncia la Corte. \u00a0<\/p>\n<p>LA \u00a0DEMANDA \u00a0<\/p>\n<p>Tras \u00a0anunciar como fines del recurso la efectividad del derecho material y \u00a0el respeto de las garant\u00edas del procesado, espec\u00edficamente, \u00a0la presunci\u00f3n de inocencia, toda vez que la sentencia \u00a0recurrida \u00a0\u201cno corresponde a \u00a0una verdadera justicia material\u201d, \u00a0formul\u00f3 \u00a0un cargo por violaci\u00f3n indirecta de la ley sustancial debido a \u00a0un error \u00a0de hecho por falso raciocinio. \u00a0<\/p>\n<p>En primer lugar, \u00a0asever\u00f3 que el testimonio de \u00c1lvaro Castrill\u00f3n \u00a0L\u00f3pez, una de las v\u00edctimas, no es consistente e impide \u00a0tener un conocimiento claro de los hechos, por dem\u00e1s, se trata \u00a0de un \u201ctestigo \u00a0de o\u00eddas\u201d, \u00a0ya que s\u00f3lo escuch\u00f3, al d\u00eda siguiente de su \u00a0cautiverio, lo que hablaba Luis Gonzalo Ram\u00edrez Hern\u00e1ndez \u00a0con un se\u00f1or, que despu\u00e9s identific\u00f3 a trav\u00e9s \u00a0de la red social Facebook. \u00a0<\/p>\n<p>Que tampoco son \u00a0consistentes las manifestaciones de Luis Gonzalo Ram\u00edrez \u00a0Hern\u00e1ndez ni se corroboran con lo dicho por Castrill\u00f3n \u00a0L\u00f3pez, sin que se pueda demostrar la presencia de SINISTERRA \u00a0MAZUERA en el lugar donde permanecieron retenidas las v\u00edctimas. \u00a0<\/p>\n<p>En \u00a0segundo t\u00e9rmino, se\u00f1al\u00f3 que el \u00a0Tribunal valor\u00f3 la prueba testimonial de manera adversa a los \u00a0postulados de la sana cr\u00edtica al desconocer la \u00a0regla de la experiencia seg\u00fan la cual \u201csi \u00a0personas que han tenido negocios, no terminan bien su relaci\u00f3n, \u00a0casi siempre se presentan inconvenientes, entonces, es muy probable \u00a0que en retaliaci\u00f3n se presenten problemas delicados, como \u00a0involucrar a otro en un delito\u201d. \u00a0<\/p>\n<p>Respecto de las \u00a0manifestaciones de Luis Alfredo Mera Fory, testigo ofrecido por la \u00a0defensa, cuestion\u00f3 la conclusi\u00f3n del juez plural \u00a0relacionada con que \u00a0\u201cnadie \u00a0celebra su cumplea\u00f1os departiendo todo un d\u00eda con una \u00a0persona que escasamente conoce\u201d, \u00a0porque en criterio del defensor, no es cierto que aqu\u00e9l apenas \u00a0conociera a GERARDO SINISTERRA MAZUERA, ya que en su declaraci\u00f3n \u00a0claramente indic\u00f3 que desde hac\u00eda varios a\u00f1os \u00a0ten\u00eda una relaci\u00f3n comercial con \u00e9l, al punto \u00a0que el 5 de mayo de 2012, departieron todo el d\u00eda por el \u00a0cumplea\u00f1os. \u00a0<\/p>\n<p>En esas \u00a0condiciones, critic\u00f3 que judicialmente no se creyera que el \u00a0enjuiciado, quien cumpl\u00eda a\u00f1os el 3 de mayo, hubiera \u00a0celebrado tal hecho el 5 de mayo de 2012 con Luis Alfredo Mera Fory, \u00a0ya que \u201cla \u00a0l\u00f3gica indica que es m\u00e1s probable celebrar el \u00a0cumplea\u00f1os un d\u00eda s\u00e1bado, que un d\u00eda \u00a0entre semana, como fue el d\u00eda jueves, pues se interfiere la \u00a0actividad laboral, mientras que el fin de semana -s\u00e1bado- no \u00a0la interfiere, pues al siguiente d\u00eda -domingo- no se labora\u201d. \u00a0<\/p>\n<p>Que tampoco se \u00a0tuvo en cuenta que Jairo Alberto Sierra en su declaraci\u00f3n \u00a0admiti\u00f3 haber hecho parte de la columna m\u00f3vil \u00a0\u201cGabriel \u00a0Galvis\u201d \u00a0de las FARC, y que hab\u00edan sido los dirigentes de esa \u00a0organizaci\u00f3n los que ordenaron el secuestro de Luis Gonzalo \u00a0Ram\u00edrez Hern\u00e1ndez, plagio en cual el que particip\u00f3 \u00a0\u201cFelipe\u201d, \u00a0tambi\u00e9n integrante de ese grupo ilegal y quien ten\u00eda la \u00a0funci\u00f3n de llevar a la v\u00edctima, a trav\u00e9s de \u00a0enga\u00f1os, al lugar donde permanecer\u00eda privado de su \u00a0libertad, como en efecto ocurri\u00f3. \u00a0<\/p>\n<p>Paralelamente, \u00a0denunci\u00f3 que en cuanto a la cantidad de dinero exigida, se \u00a0pas\u00f3 por alto la regla de la experiencia que \u201ccasi \u00a0siempre que las v\u00edctimas de un secuestro extorsivo econ\u00f3mico \u00a0carecen de dinero efectivo, entonces las exigencias se cambia por \u00a0bienes materiales\u201d, \u00a0para restarle as\u00ed credibilidad a la declaraci\u00f3n de \u00a0Jairo Alberto Sierra, al se\u00f1alar que no pudo explicar por qu\u00e9, \u00a0si el objetivo del secuestro era que Luis Gonzalo Ram\u00edrez \u00a0Hern\u00e1ndez entregara los $400.000.000 que ten\u00eda producto \u00a0del narcotr\u00e1fico, tambi\u00e9n le fueron exigidas las \u00a0escrituras de unas casas que estaban a su nombre y el traspaso de \u00a0unos automotores. \u00a0<\/p>\n<p>En \u00a0raz\u00f3n de lo anterior, solicit\u00f3 a la Corte casar el \u00a0fallo recurrido y emitir decisi\u00f3n de reemplazo de car\u00e1cter \u00a0absolutorio en favor de su asistido. \u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE LA CORTE \u00a0<\/p>\n<p>Aunque \u00a0el demandante refiere como fines de la impugnaci\u00f3n \u00a0extraordinaria la efectividad del derecho material y el respeto de \u00a0las garant\u00edas debidas a su asistido, en cuanto estima que la \u00a0sentencia \u00a0\u201cno \u00a0corresponde a una verdadera justicia material\u201d, \u00a0no se advierte la relaci\u00f3n de tales postulados con el cargo \u00a0que formula, porque si bien denuncia la pretermisi\u00f3n judicial \u00a0de los postulados de la sana cr\u00edtica, su postura se queda en \u00a0una oposici\u00f3n a la valoraci\u00f3n probatoria, sin demostrar \u00a0el desafuero intelectivo del Tribunal. \u00a0<\/p>\n<p>En \u00a0efecto, cuestiona el m\u00e9rito suasorio dado a los testimonios de \u00a0las v\u00edctimas, Luis \u00a0Gonzalo Ram\u00edrez Hern\u00e1ndez y \u00c1lvaro Castrill\u00f3n \u00a0L\u00f3pez, al considerar que sus manifestaciones no fueron \u00a0consistentes, \u00a0pero en vez de explicar c\u00f3mo los juzgadores se apartaron de \u00a0las \u00a0leyes de la ciencia, los principios de la l\u00f3gica o las reglas \u00a0de la experiencia en la apreciaci\u00f3n de las mismas, el defensor \u00a0se conforma con transcribir \u00a0in \u00a0extenso tales \u00a0pruebas, quedando as\u00ed hu\u00e9rfana la demostraci\u00f3n \u00a0del error judicial. \u00a0<\/p>\n<p>No \u00a0se detiene en el an\u00e1lisis probatorio que encontr\u00f3 \u00a0fiabilidad en el relato de los hechos ofrecido por Luis \u00a0Gonzalo Ram\u00edrez Hern\u00e1ndez, \u00a0por ser quien habl\u00f3 personalmente con SINISTERRA MAZUERA en el \u00a0lugar donde estuvo en cautiverio por dos d\u00edas, m\u00e1xime \u00a0que no era una persona desconocida ya que se trataba de su concu\u00f1ado, \u00a0pues estaba casado con una hermana de la primera esposa de Ram\u00edrez. \u00a0<\/p>\n<p>Tampoco \u00a0el casacionista intenta \u00a0derruir la conclusi\u00f3n del Tribunal tomada del detalle de la \u00a0informaci\u00f3n suministrada por ese testigo y su contraste con \u00a0otros elementos de convicci\u00f3n, como la declaraci\u00f3n del \u00a0otro afectado \u00c1lvaro \u00a0Castrill\u00f3n L\u00f3pez, quien durante su cautiverio, \u00a0efectivamente solo escuch\u00f3, porque no vio, cuando lleg\u00f3 \u00a0un se\u00f1or al apartamento donde permaneci\u00f3 secuestrado y \u00a0discuti\u00f3 en la habitaci\u00f3n contigua con Luis Gonzalo \u00a0Ram\u00edrez Hern\u00e1ndez sobre unos asuntos pendientes o \u00a0negocios en el exterior, reclam\u00e1ndole a su amigo Ram\u00edrez \u00a0Hern\u00e1ndez por haber estado detenido en Estados Unidos. \u00a0<\/p>\n<p>Por eso, para las \u00a0instancias \u00c1lvaro \u00a0Castrill\u00f3n L\u00f3pez \u00a0no era un \u201ctestigo \u00a0de o\u00eddas\u201d, \u00a0como erradamente lo califica el demandante. Se trataba de prueba \u00a0directa de lo que \u00e9l mismo percibi\u00f3 desde la habitaci\u00f3n \u00a0contigua en el inmueble que compart\u00eda el cautiverio con Luis \u00a0Gonzalo Ram\u00edrez Hern\u00e1ndez, cuando escuch\u00f3 la \u00a0discusi\u00f3n que \u00e9ste tuvo con alguien, por dem\u00e1s, \u00a0previamente hab\u00eda presenciado cuando sus captores le cobraban \u00a0a aqu\u00e9l un dinero que presuntamente le deb\u00eda a un \u00a0conocido y le exig\u00edan la entrega de las escrituras y el \u00a0traspaso de los automotores que estuvieran a su nombre. \u00a0<\/p>\n<p>No \u00a0se detiene en las consideraciones del juez plural que bas\u00f3 la \u00a0credibilidad de las manifestaciones de \u00c1lvaro Castrill\u00f3n \u00a0L\u00f3pez por la espontaneidad de su narraci\u00f3n, sin que se \u00a0advirtiera que la misma obedeciera a un \u00a0libreto previamente establecido o que tuviera alg\u00fan \u00e1nimo \u00a0protervo de querer perjudicar al procesado. \u00a0<\/p>\n<p>As\u00ed \u00a0mismo, no dirige alg\u00fan embate a la estimaci\u00f3n judicial \u00a0relacionada con que Luis Gonzalo Ram\u00edrez Hern\u00e1ndez en \u00a0su declaraci\u00f3n en la audiencia de juicio oral reconoci\u00f3 \u00a0que su secuestro obedeci\u00f3 a las \u00a0diferencias que mediaban con GERARDO \u00a0SINISTERRA MAZUERA desde cuando estuvieron privados de la libertad en \u00a0Estados Unidos, circunstancia que \u00e9ste \u00faltimo le hab\u00eda \u00a0manifestado en su plagio al decirle que deb\u00eda pagar por el \u00a0tiempo que \u00e9l hab\u00eda estado en prisi\u00f3n. \u00a0<\/p>\n<p>La \u00a0postura del casacionista carece de una base racional \u00a0alternativa capaz de derruir las consideraciones del fallador, lo \u00a0cual se corrobora cuando tambi\u00e9n cuestiona el cr\u00e9dito \u00a0dado a las declaraciones de los testigos de descargo Jairo \u00a0Alberto Sierra y Luis Alfredo Mera Fory, pues aunque a manera de \u00a0regla de la experiencia se\u00f1ala fue desconocido que \u201csi \u00a0personas que han tenido negocios, no terminan bien su relaci\u00f3n, \u00a0casi siempre se presentan inconvenientes, entonces, es muy probable \u00a0que en retaliaci\u00f3n se presenten problemas delicados, como \u00a0involucrar a otro en un delito\u201d, \u00a0no explica por qu\u00e9 ese postulado debe ser catalogado como tal \u00a0por tener la caracter\u00edstica de generalidad en contextos \u00a0similares y tendr\u00eda plena aplicaci\u00f3n en este caso. \u00a0Igual \u00a0acontece cuando tan solo anuncia que fue desconocida la \u00a0regla de la experiencia relacionada con que \u201ccasi \u00a0siempre que las v\u00edctimas de un secuestro extorsivo econ\u00f3mico, \u00a0carecen de dinero efectivo, entonces la exigencia se cambia por \u00a0bienes materiales\u201d, \u00a0pues no dedic\u00f3 espacio para acreditar su universalidad. \u00a0<\/p>\n<p>La precariedad \u00a0demostrativa de la impugnaci\u00f3n le resta al cargo la idoneidad \u00a0necesaria para su admisi\u00f3n al no acreditar el recurrente el \u00a0error del Tribunal por no haber hecho eco a la \u00a0tesis defensiva que SINISTERRA \u00a0MAZUERA era ajeno a los hechos y que el \u00a0secuestro hab\u00eda sido ordenado por la columna \u201cGabriel \u00a0Galvis\u201d \u00a0de las FARC, porque en el fallo al valorar el testimonio \u00a0de Jairo Alberto Sierra \u2014capturado en el operativo del Gaula la \u00a0noche del 5 de mayo de 2012 y condenado por el delito de secuestro\u2014, \u00a0quien afirm\u00f3 que esa organizaci\u00f3n \u00a0se hab\u00eda enterado que \u00c1lvaro Castrill\u00f3n hab\u00eda \u00a0llegado con dinero de narcotr\u00e1fico y por eso decidieron \u00a0secuestrarlo para exigirle $400.000.000, se concluy\u00f3 que tales \u00a0manifestaciones eran ambiguas y gaseosas \u201cpues \u00a0no pudo precisar ni explicar satisfactoriamente la ciencia de su \u00a0dicho y termin\u00f3 diciendo en t\u00e9rminos gen\u00e9ricos \u00a0que fue \u2018una \u00a0operaci\u00f3n de la organizaci\u00f3n\u2019 \u00a0pero de manera evasiva dijo no saber los nombres de ninguno de los \u00a0que pudieron haber intervenido en el hecho ni pudo explicar c\u00f3mo \u00a0es que, si la noticia que hab\u00eda recibido \u00a0\u2018la \u00a0organizaci\u00f3n\u2019 era que Ram\u00edrez Hern\u00e1ndez \u00a0hab\u00eda llegado con plata del narcotr\u00e1fico, se centraron \u00a0en pedirle las escrituras de los inmuebles urbanos y de la finca y \u00a0los documentos de los carros\u201d. \u00a0<\/p>\n<p>Por \u00a0dem\u00e1s, el Tribunal destac\u00f3 que ese relato no guardaba \u00a0correspondencia con lo probado, espec\u00edficamente, con las \u00a0manifestaciones de las v\u00edctimas quienes coincid\u00edan en \u00a0que fueron interceptadas cuando transitaban por la Av. Sim\u00f3n \u00a0Bol\u00edvar con carrera 23 y sometidas con arma de fuego dentro \u00a0del carro que conduc\u00eda \u00c1lvaro Castrill\u00f3n, siendo \u00a0llevadas a un inmueble donde los tuvieron retenidos, precisando \u00a0\u00c1lvaro Castrill\u00f3n que lo torturaron al presionarle las \u00a0tetillas con un alicate quemarle con cigarrillo las orejas y el \u00a0cuello para que accediera a entregar las escrituras de las inmuebles \u00a0y los documentos de los veh\u00edculos, a lo que se sumaba el \u00a0requerimiento vindicativo que directamente le hizo SINISTERRA \u00a0MAZUERA. \u00a0<\/p>\n<p>Y en cuanto a no \u00a0haber merecido credibilidad la afirmaci\u00f3n de Luis \u00a0Alfredo Mera Fory cuando se\u00f1al\u00f3 que comparti\u00f3 \u00a0todo el d\u00eda 5 de mayo de 2012 con SINISTERRA MAZUERA, \u00a0celebr\u00e1ndole el cumplea\u00f1os, lo que seg\u00fan el \u00a0defensor desconoce la \u201cl\u00f3gica\u201d \u00a0seg\u00fan \u00a0la cual \u201ces \u00a0m\u00e1s probable celebrar el cumplea\u00f1os un d\u00eda \u00a0s\u00e1bado, que un d\u00eda entre semana\u201d, \u00a0pasa por alto que la fiabilidad del atestante fue derruida por la \u00a0vaguedad de su relato evidenciada \u00a0al no tener claridad y precisi\u00f3n sobre la manera como \u00a0supuestamente conoci\u00f3 al acusado y porque no resultaba \u00a0ajustado que si lo conoc\u00eda de vieja data no supiera cuando \u00a0menos el nombre de la c\u00f3nyuge del implicado o la direcci\u00f3n \u00a0de su residencia, entre otros, lo que hac\u00eda improbable que \u00a0efectivamente hubiera estado con \u00e9l todo un d\u00eda en tal \u00a0celebraci\u00f3n. \u00a0<\/p>\n<p>Deviene \u00a0as\u00ed di\u00e1fano que las quejas del impugnante no tienen \u00a0sustento en factores objetivos y corresponden s\u00f3lo a una \u00a0alegaci\u00f3n defensiva distante de se\u00f1alar graves yerros \u00a0de los juzgadores en la valoraci\u00f3n probatoria. \u00a0<\/p>\n<p>Al \u00a0respecto, la Corte ha enfatizado en que las discrepancias con las \u00a0consideraciones judiciales no son por s\u00ed solas suficientes \u00a0para invalidar el fallo, pues corresponde al demandante \u00a0desvirtuarlas, no mediante una argumentaci\u00f3n libre y propia de \u00a0las instancias ordinarias, sino con sujeci\u00f3n a las t\u00e9cnicas \u00a0establecidas para probar la existencia de yerros manifiestos y \u00a0esenciales, ejercicio que en este no acometi\u00f3 cabalmente el \u00a0recurrente y que de contera hace inviable la admisi\u00f3n de la \u00a0demanda. \u00a0<\/p>\n<p>Por \u00a0\u00faltimo, vale la pena rese\u00f1ar que si bien SINISTERRA \u00a0MAZUERA fue acusado como coautor del concurso delictual de secuestro \u00a0extorsivo agravado2, \u00a0pero condenado en calidad de determinador del mismo, no se advierte \u00a0alguna transgresi\u00f3n de entidad en relaci\u00f3n con el \u00a0principio de congruencia, pues tal variaci\u00f3n no le gener\u00f3 \u00a0alg\u00fan perjuicio ya que ambas categor\u00edas tienen los \u00a0mismos efectos punitivos, y precisamente con las pruebas debatidas en \u00a0desarrollo del juicio oral se encontr\u00f3 que el incriminado fue \u00a0quien \u00a0orden\u00f3 el secuestro de Luis Gonzalo \u00a0Ram\u00edrez Hern\u00e1ndez \u00a0y, consecuentemente, el de \u00c1lvaro Castrill\u00f3n. \u00a0<\/p>\n<p>En \u00a0estas condiciones, no se ve la necesidad de superar los defectos que \u00a0exhibe la demanda para decidir de fondo, seg\u00fan lo dispone el \u00a0inciso 3\u00ba del art\u00edculo 184 de la Ley 906 de 2004 que \u00a0ameritara la intervenci\u00f3n oficiosa de la Corte, pues se \u00a0advierte razonablemente que no se precisa del fallo para cumplir \u00a0alguna de las finalidades del recurso de casaci\u00f3n: i) \u00a0la efectividad del derecho material; ii) \u00a0el respeto de las garant\u00edas de los intervinientes; iii) \u00a0la reparaci\u00f3n de los agravios inferidos a estos; o iv) \u00a0la unificaci\u00f3n de la jurisprudencia. \u00a0<\/p>\n<p>Precisi\u00f3n \u00a0final \u00a0<\/p>\n<p>De \u00a0conformidad con el Decreto Legislativo 546 del 14 de abril de 2020, \u00a0que, en el marco del Estado de Emergencia Econ\u00f3mica, Social y \u00a0Ecol\u00f3gica en virtud del COVID-19, dispuso, entro otros \u00a0aspectos, la sustituci\u00f3n transitoria de la pena de prisi\u00f3n \u00a0por la prisi\u00f3n domiciliaria, y como quiera que en el presente \u00a0caso se procede por un delito expresamente exceptuado de tal \u00a0beneficio en el art\u00edculo 6\u00b0, esto es, el secuestro \u00a0extorsivo agravado, SINISTERRA MAZUERA no se har\u00eda acreedor de \u00a0tal medida. \u00a0<\/p>\n<p>Contra \u00a0la decisi\u00f3n de no admitir la demanda de casaci\u00f3n \u00a0procede el mecanismo de insistencia de conformidad con lo establecido \u00a0en el art\u00edculo 184 de la Ley 906 de 2004. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, Sala de \u00a0Casaci\u00f3n Penal, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>NO \u00a0ADMITIR \u00a0la demanda de casaci\u00f3n interpuesta por el defensor de GERARDO \u00a0SINISTERRA MAZUERA por las razones dadas en la anterior motivaci\u00f3n. \u00a0<\/p>\n<p>De \u00a0conformidad con lo dispuesto en el art\u00edculo 184 de la Ley 906 \u00a0de 2004, es facultad de la demandante elevar petici\u00f3n de \u00a0insistencia. \u00a0<\/p>\n<p>Notif\u00edquese \u00a0y c\u00famplase \u00a0<\/p>\n<p>PATRICIA \u00a0SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>GERSON \u00a0CHAVERRA CASTRO \u00a0<\/p>\n<p>EUGENIO \u00a0FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>LUIS \u00a0ANTONIO HERN\u00c1NDEZ BARBOSA \u00a0<\/p>\n<p>JAIME HUMBERTO \u00a0MORENO ACERO \u00a0<\/p>\n<p>FABIO \u00a0OSPITIA GARZ\u00d3N \u00a0<\/p>\n<p>EYDER \u00a0PATI\u00d1O CABRERA \u00a0<\/p>\n<p>HUGO \u00a0QUINTERO BERNATE \u00a0<\/p>\n<p>NUBIA \u00a0YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jairo Alberto Sierra y Vladimir Pinz\u00f3n L\u00f3pez, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0quienes en tr\u00e1mite separado fueron condenados por estos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0hechos (la actuaci\u00f3n no registra informaci\u00f3n detallada \u00a0 \u00a0 \u00a0 \u00a0 \u00a0al respecto).\u00a0 \u00a0<\/p>\n<p>2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0A pesar de la impropiedad terminol\u00f3gica del fiscal cuando lo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ubic\u00f3 como \u201cautor \u00a0 \u00a0 \u00a0 \u00a0 \u00a0intelectual del reato de secuestro extorsivo\u201d. \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 EUGENIO \u00a0FERN\u00c1NDEZ CARLIER \u00a0 Magistrado \u00a0ponente \u00a0 AP1888-2020 \u00a0 Radicaci\u00f3n \u00a0N\u00ba 54143 \u00a0 Acta\u00a0166\u00a0 \u00a0 \u00a0 \u00a0 Bogot\u00e1,\u00a0D.\u00a0C.,\u00a0doce \u00a0(12) de agosto\u00a0de dos mil veinte (2020).\u00a0 \u00a0 Decide \u00a0la Sala la admisibilidad de los fundamentos l\u00f3gicos y de \u00a0adecuada argumentaci\u00f3n de la demanda de casaci\u00f3n \u00a0presentada por el defensor de GERARDO SINISTERRA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-50229","post","type-post","status-publish","format-standard","hentry","category-29"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/50229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=50229"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/50229\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=50229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=50229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=50229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}