{"id":45849,"date":"2023-09-14T21:58:11","date_gmt":"2023-09-14T21:58:11","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/14\/stp13642-2019\/"},"modified":"2023-09-14T21:58:11","modified_gmt":"2023-09-14T21:58:11","slug":"stp13642-2019","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/14\/stp13642-2019\/","title":{"rendered":"STP13642-2019"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>PATRICIA \u00a0SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>Magistrada \u00a0Ponente \u00a0 \u00a0 \u00a0<\/p>\n<p>STP13642-2019 \u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0N.\u00ba 107042 \u00a0<\/p>\n<p>Acta \u00a0260 \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D. C., cuatro (4) de octubre de dos mil diecinueve (2019). \u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Se \u00a0pronuncia la Sala sobre la impugnaci\u00f3n propuesta por DARWIN \u00a0RAFAEL PE\u00d1ARANDA CALDER\u00d3N, \u00a0contra el fallo proferido el 3 de septiembre del a\u00f1o que \u00a0avanza por la SALA \u00a0PENAL DEL TRIBUNAL SUPERIOR DE TUNJA, \u00a0mediante el cual neg\u00f3 la demanda de tutela promovida por \u00e9l \u00a0y por SA\u00daL \u00a0ANTONIO BUELVAS ROMERO contra \u00a0los JUZGADOS \u00a0SEGUNDO DE EJECUCI\u00d3N DE PENAS Y MEDIDAS DE SEGURIDAD DE \u00a0CARTAGENA y SEGUNDO DE LA MISMA ESPECIALIDAD DE MONTER\u00cdA, \u00a0ante la supuesta vulneraci\u00f3n de sus derechos fundamentales. \u00a0<\/p>\n<p>ANTECEDENTES \u00a0Y FUNDAMENTOS \u00a0<\/p>\n<p>SA\u00daL \u00a0ANTONIO BUELVAS ROMERO y DARWIN RAFAEL PE\u00d1ARANDA CALDER\u00d3N \u00a0est\u00e1n actualmente privados de la libertad en el \u00a0establecimiento carcelario de C\u00f3mbita, pero advierten que los \u00a0jueces de ejecuci\u00f3n de penas de Monter\u00eda y Cartagena \u00a0que vigilaban las condenas que les fueron impuestas, no han ordenado \u00a0la remisi\u00f3n de las diligencias a los funcionarios de la misma \u00a0especialidad de Tunja, lo que les ha impedido elevar solicitudes de \u00a0beneficios punitivos. \u00a0<\/p>\n<p>Piden \u00a0al juez de tutela, para superar la lesi\u00f3n de sus derechos \u00a0fundamentales, que se ordene a los involucrados el env\u00edo de \u00a0los expedientes a los jueces ejecutores de la ciudad de Tunja. \u00a0<\/p>\n<p>EL \u00a0FALLO IMPUGNADO \u00a0<\/p>\n<p>El \u00a0Tribunal Superior de Tunja neg\u00f3 la tutela al advertir la \u00a0carencia actual de objeto de protecci\u00f3n constitucional, porque \u00a0de las respuestas que allegaron al tr\u00e1mite las autoridades que \u00a0integraron el contradictorio, constat\u00f3 que se hab\u00edan \u00a0resuelto los reclamos de los demandantes. \u00a0<\/p>\n<p>Dijo, \u00a0en ese sentido, que los expedientes hab\u00edan sido remitidos a \u00a0los jueces de ejecuci\u00f3n de penas de Tunja y por ende, no era \u00a0necesaria la intervenci\u00f3n del juez de amparo. \u00a0<\/p>\n<p>LA \u00a0IMPUGNACI\u00d3N \u00a0<\/p>\n<p>Al \u00a0ser notificado del fallo, DARWIN RAFAEL PE\u00d1ARANDA CALDER\u00d3N \u00a0escribi\u00f3 la palabra \u00abapelo\u00bb. \u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE LA CORTE \u00a0<\/p>\n<p>1. \u00a0De conformidad con lo establecido en el art\u00edculo 32 del \u00a0Decreto 2591 de 19911, \u00a0la Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia es \u00a0competente para resolver la impugnaci\u00f3n interpuesta contra el \u00a0fallo proferido por la Sala Penal del Tribunal Superior de Tunja. \u00a0<\/p>\n<p>2. \u00a0Para el caso concreto, ninguna irregularidad se advierte en punto de \u00a0las quejas formuladas por los accionantes ante la supuesta afectaci\u00f3n \u00a0de sus derechos fundamentales. \u00a0<\/p>\n<p>En \u00a0ese sentido, como se constata de las respuestas que dentro del \u00a0proceso de amparo emitieron los Juzgados Segundo de Ejecuci\u00f3n \u00a0de Penas de Monter\u00eda y Segundo de la misma especialidad de \u00a0Cartagena, los expedientes mediante los cuales se vigilan las \u00a0condenas impuestas a BUELVAS ROMERO y PE\u00d1ARANDA CALDER\u00d3N, \u00a0fueron enviados a los despachos judiciales de Tunja. \u00a0<\/p>\n<p>Adem\u00e1s, \u00a0se constata en el sistema de consulta de actuaciones de la Rama \u00a0Judicial, que tales asuntos ya se encuentran en el Distrito Judicial \u00a0de Tunja, el expediente de BUELVAS ROMERO fue asignado al juez \u00a0tercero de ejecuci\u00f3n de penas y el que corresponde a PE\u00d1ARANDA \u00a0CALDER\u00d3N, al Juzgado Sexto, ambos de la ciudad en cita. \u00a0<\/p>\n<p>Entonces, \u00a0como acertadamente expuso el Tribunal a \u00a0quo, se remediaron \u00a0las afectaciones que eran el eje central del reclamo constitucional \u00a0propuesto por el accionante y por consiguiente, es evidente la \u00a0improcedencia del amparo por carencia actual de objeto, en tanto se \u00a0configura en el caso el fen\u00f3meno de hecho superado, que se \u00a0produce \u00abcuando \u00a0entre el momento de la interposici\u00f3n \u00a0de la acci\u00f3n de tutela y el \u00a0momento del fallo \u00a0se satisface por completo la pretensi\u00f3n contenida en la \u00a0demanda de amparo\u00bb \u00a0(CC \u00a0T-200\/13). \u00a0<\/p>\n<p>Por \u00a0ende, la decisi\u00f3n recurrida se confirmar\u00e1 en su \u00a0integridad. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, LA \u00a0CORTE SUPREMA DE JUSTICIA, SALA DE CASACI\u00d3N PENAL \u2013 EN \u00a0SALA DE DECISI\u00d3N DE ACCIONES DE TUTELA No. 2, \u00a0administrando justicia en nombre de la Rep\u00fablica y por \u00a0autoridad de la Ley, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>CONFIRMAR \u00a0el \u00a0fallo impugnado. \u00a0<\/p>\n<p>NOTIFICAR \u00a0esta \u00a0providencia de conformidad con el art\u00edculo 30 del Decreto 2591 \u00a0de 1991. \u00a0<\/p>\n<p>REMITIR \u00a0el \u00a0expediente a la Corte Constitucional para su eventual revisi\u00f3n, \u00a0una vez en firme. \u00a0<\/p>\n<p>NOTIF\u00cdQUESE \u00a0y C\u00daMPLASE \u00a0<\/p>\n<p>LUIS \u00a0ANTONIO HERN\u00c1NDEZ BARBOSA \u00a0<\/p>\n<p>PATRICIA \u00a0SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>NUBIA \u00a0YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Tr\u00e1mite de la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0impugnaci\u00f3n. Presentada debidamente la impugnaci\u00f3n el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0juez remitir\u00e1 el expediente dentro de los dos d\u00edas \u00a0 \u00a0 \u00a0 \u00a0 \u00a0siguientes al superior jer\u00e1rquico correspondiente. \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 PATRICIA \u00a0SALAZAR CU\u00c9LLAR \u00a0 Magistrada \u00a0Ponente \u00a0 \u00a0 \u00a0 STP13642-2019 \u00a0 Radicaci\u00f3n \u00a0N.\u00ba 107042 \u00a0 Acta \u00a0260 \u00a0 Bogot\u00e1, \u00a0D. C., cuatro (4) de octubre de dos mil diecinueve (2019). \u00a0 VISTOS \u00a0 Se \u00a0pronuncia la Sala sobre la impugnaci\u00f3n propuesta por DARWIN \u00a0RAFAEL PE\u00d1ARANDA CALDER\u00d3N, \u00a0contra el fallo proferido el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-45849","post","type-post","status-publish","format-standard","hentry","category-28"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/45849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=45849"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/45849\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=45849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=45849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=45849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}