{"id":4491,"date":"2023-09-08T15:14:36","date_gmt":"2023-09-08T15:14:36","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1670305-09-01\/"},"modified":"2023-09-08T15:14:36","modified_gmt":"2023-09-08T15:14:36","slug":"1670305-09-01","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1670305-09-01\/","title":{"rendered":"16703(05-09-01)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso N\u00b0 16703 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>Dr. \u00a0JORGE \u00a0E. \u00a0C\u00d3RDOBA \u00a0POVEDA \u00a0\u00a0<\/p>\n<p>Aprobado acta N\u00b0 133 \u00a0<\/p>\n<p>Bogot\u00e1, D. C., cinco (5) de septiembre de dos \u00a0mil uno (2001). \u00a0\u00a0<\/p>\n<p>V \u00a0 \u00a0I \u00a0 S \u00a0 TO \u00a0 S \u00a0\u00a0<\/p>\n<p>Resuelve \u00a0la \u00a0Sala \u00a0la \u00a0solicitud \u00a0de pruebas \u00a0elevada \u00a0 en \u00a0 el \u00a0 tr\u00e1mite \u00a0 de \u00a0 extradici\u00f3n \u00a0 del \u00a0 ciudadano \u00a0SANTIAGO \u00a0V\u00c9LEZ \u00a0VEL\u00c1SQUEZ. Igualmente se \u00a0atender\u00e1 otra petici\u00f3n. \u00a0\u00a0<\/p>\n<p>A \u00a0N \u00a0T \u00a0E \u00a0C E D E N T E \u00a0S \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. El Gobierno de los Estados Unidos de \u00a0Am\u00e9rica, \u00a0mediante \u00a0Notas \u00a0Verbales n\u00fameros 1058 y 1211 del 7 de octubre y del \u00a026 \u00a0de \u00a0noviembre \u00a0de \u00a01999, \u00a0por conducto de su Embajada en Colombia, solicit\u00f3 \u00a0formalmente \u00a0 la \u00a0 extradici\u00f3n \u00a0 del \u00a0 ciudadano \u00a0 colombiano \u00a0Santiago \u00a0V\u00e9lez \u00a0Vel\u00e1squez. \u00a0\u00a0<\/p>\n<p>2. Con \u00a0oficio del 1\u00b0 de diciembre de \u00a01999, \u00a0el \u00a0Ministerio \u00a0de \u00a0Justicia \u00a0y \u00a0del \u00a0Derecho \u00a0remiti\u00f3 la documentaci\u00f3n \u00a0relacionada \u00a0con \u00a0la solicitud de extradici\u00f3n presentada, demandando de la Sala \u00a0el respectivo concepto. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. Corrido \u00a0el \u00a0traslado \u00a0para \u00a0pedir \u00a0pruebas \u00a0 (art. \u00a0 556 \u00a0 del \u00a0 C. \u00a0 de \u00a0 P. \u00a0 P.), \u00a0 su \u00a0 defensor \u00a0solicita \u00a0las \u00a0siguientes: \u00a0 \u00a0\u00a0<\/p>\n<p>Primer escrito \u00a0<\/p>\n<p>3.1. En el ac\u00e1pite que titula \u201cPRE\u00c1MBULO\u201d, sostiene que cuando asumi\u00f3 \u00a0la \u00a0defensa de V\u00e9lez Vel\u00e1squez encontr\u00f3 que el diligenciamiento no se hallaba \u00a0perfeccionado, \u00a0raz\u00f3n \u00a0por la cual solicit\u00f3 su devoluci\u00f3n. Por ese motivo, no \u00a0entiende\u00a0 \u00a0el \u00a0por \u00a0qu\u00e9 \u00a0se \u00a0dice \u00a0que ha realizado pr\u00e1cticas dilatorias, \u00a0m\u00e1xime \u00a0cuando \u00a0el funcionario judicial tiene la direcci\u00f3n del proceso y puede \u00a0rechazar de plano las peticiones. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s \u00a0como constancia de lo expuesto, dice \u00a0que \u00a0a \u00a0su \u00a0representado \u00a0no \u00a0se \u00a0le notific\u00f3 debidamente el auto que abri\u00f3 el \u00a0tr\u00e1mite a pruebas. \u00a0\u00a0<\/p>\n<p>3.2. \u00a0 En \u00a0 el \u00a0 t\u00edtulo \u00a0 que \u00a0 denomin\u00f3 \u00a0\u201cDE \u00a0 LA \u00a0 RESOLUCI\u00d3N \u00a0 DE \u00a0ACUSACI\u00d3N\u201d, \u00a0luego \u00a0de \u00a0enunciar \u00a0cu\u00e1les \u00a0son \u00a0sus \u00a0requisitos \u00a0conforme a \u00a0nuestra \u00a0legislaci\u00f3n, al tenor de lo reglado en el art\u00edculo 441 del C\u00f3digo de \u00a0Procedimiento \u00a0Penal, \u00a0advierte que el indictment no re\u00fane dichos presupuestos, \u00a0pues, \u00a0a \u00a0su \u00a0juicio, \u00a0los \u00a0cargos \u00a0que \u00a0all\u00ed \u00a0se \u00a0formulan son \u201cindeterminados \u00a0y \u00a0gaseosos \u00a0lo \u00a0cual conlleva a la indeterminaci\u00f3n \u00a0del \u00a0hecho \u00a0mismo \u00a0que \u00a0no \u00a0es \u00a0admitido \u00a0en \u00a0nuestro \u00a0derecho penal\u201d. \u00a0Como \u00a0sustento \u00a0de \u00a0su \u00a0aserto \u00a0procede a copiar varios de sus \u00a0apartes \u00a0y \u00a0a \u00a0resaltar \u00a0los hechos imputados en los cargos tercero y cuarto, en \u00a0cuanto \u00a0a \u00a0los \u00a0comportamientos \u00a0delictivos \u00a0imputados y a las circunstancias de \u00a0modo, tiempo y lugar en que ocurrieron. \u00a0\u00a0<\/p>\n<p>Por lo expuesto, asevera que el indictment que \u00a0obra \u00a0en \u00a0el presente tr\u00e1mite no es equivalente a la resoluci\u00f3n de acusaci\u00f3n, \u00a0al \u00a0no \u00a0reunir las \u201cformalidades extr\u00ednsecas porque, \u00a0como \u00a0vimos \u00a0no \u00a0est\u00e1 claro el modo, tiempo y lugar de los hechos extr\u00ednsecos, \u00a0lo \u00a0 cual \u00a0 crea \u00a0 una \u00a0 indeterminaci\u00f3n \u00a0que \u00a0debe \u00a0ser \u00a0corregida\u201d. \u00a0Adem\u00e1s, \u00a0agrega, \u00a0no \u00a0contiene \u00a0el \u00a0requisito \u00a0exigido \u00a0en el \u00a0numeral 2\u00b0 del art\u00edculo 442 del C. de P. Penal. \u00a0\u00a0<\/p>\n<p>3.3. \u00a0 En \u00a0 otro \u00a0 cap\u00edtulo \u00a0 que \u00a0 llama \u00a0\u201cDEL \u00a0 \u00a0DERECHO \u00a0 \u00a0A \u00a0 \u00a0LA \u00a0 \u00a0DEFENSA\u201d, \u00a0despu\u00e9s \u00a0de \u00a0manifestar \u00a0que \u00a0la Sala en m\u00faltiples fallos ha \u00a0sostenido \u00a0que \u00a0la \u00a0mayor \u00a0garant\u00eda para el procesado es el derecho de defensa, \u00a0anota \u00a0que \u00a0la documentaci\u00f3n allegada por las autoridades de los Estados Unidos \u00a0de \u00a0Am\u00e9rica \u00a0para \u00a0legalizar \u00a0la \u00a0extradici\u00f3n de su protegido, no cumpli\u00f3 con \u00a0dicho \u00a0postulado, \u00a0transgredi\u00e9ndose \u00a0lo \u00a0preceptuado \u00a0en \u00a0el \u00a0numeral \u00a02\u00b0 \u00a0del \u00a0art\u00edculo \u00a0 549 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0por \u00a0lo \u00a0que \u00a0se \u00a0hace \u00a0indispensable \u00a0que \u00a0la \u00a0Corte \u00a0los \u00a0requiera a fin de que complementen la citada \u00a0documentaci\u00f3n, \u00a0 \u00a0pues \u00a0 se \u00a0 est\u00e1 \u00a0 en \u00a0 la \u00a0 incertidumbre \u00a0 \u201cde \u00a0cu\u00e1les \u00a0son \u00a0los \u00a0verdaderos \u00a0cargos \u00a0o \u00a0hechos \u00a0imputados a mi \u00a0defendido \u00a0y \u00a0cu\u00e1les \u00a0las pruebas que se tuvieron presente para procederse a la \u00a0elevaci\u00f3n \u00a0de \u00a0los \u00a0cargos \u00a0descritos, \u00a0incertidumbre que viola directamente el \u00a0derecho \u00a0de \u00a0defensa y que no se concibe dentro de la resoluci\u00f3n de acusaci\u00f3n, \u00a0porque \u00a0 si \u00a0 se \u00a0 llegase \u00a0 a \u00a0presentar \u00a0en \u00a0esa \u00a0forma \u00a0estar\u00eda \u00a0viciada \u00a0de \u00a0nulidad\u201d. \u00a0\u00a0<\/p>\n<p>Igualmente \u00a0estima \u00a0que no se \u201cest\u00e1 \u00a0probando\u201d la clase de elemento que \u00a0se \u00a0 \u00a0dice \u00a0 \u00a0negoci\u00f3, \u00a0 \u00a0al \u00a0 \u00a0no \u00a0 \u00a0haberse \u00a0 \u00a0determinado \u00a0 \u00a0\u201cmediante \u00a0 incautaci\u00f3n \u00a0 o \u00a0 por \u00a0 otros \u00a0medios \u00a0probatorios \u00a0como \u00a0testimonio \u00a0 o \u00a0 la \u00a0 confesi\u00f3n, \u00a0 quedando \u00a0 indeterminado \u00a0 el \u00a0 cuerpo \u00a0 del \u00a0delito\u201d, \u00a0 aspecto \u00a0 que \u00a0 no \u00a0sucede \u00a0con \u00a0nuestra \u00a0resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n, \u00a0pues, \u00a0caso \u00a0contrario, \u00a0se \u00a0estar\u00eda acusando por \u00a0hechos no comprobados. \u00a0\u00a0<\/p>\n<p>3.4. \u00a0 En \u00a0 la \u00a0 secci\u00f3n \u00a0 que \u00a0 denomina \u00a0\u201cTR\u00c1MITE \u00a0 \u00a0DE \u00a0 \u00a0LA \u00a0 \u00a0EXTRADICI\u00d3N\u201d, \u00a0afirma \u00a0que\u00a0 \u00a0en \u00a0la fase preliminar, la que se cumple en \u00a0los \u00a0Ministerios \u00a0de \u00a0Relaciones \u00a0Exteriores y de Justicia y del Derecho y en la \u00a0Fiscal\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0y \u00a0en \u00a0la \u00a0que \u00a0el Estado requirente puede \u00a0solicitar \u00a0 la \u00a0 \u201cdetenci\u00f3n \u00a0preventiva\u201d \u00a0con fines de extradici\u00f3n, dichas autoridades tiene un lapso de \u00a060 \u00a0d\u00edas \u00a0para \u00a0perfeccionar \u00a0o \u00a0legalizar la solicitud y no se pueden deprecar \u00a0pruebas, \u00a0conforme \u00a0lo \u00a0ha \u00a0dispuesto \u00a0la \u00a0jurisprudencia de la Corte, lo que lo \u00a0lleva \u00a0 \u00a0 a \u00a0 \u00a0 colegir \u00a0 \u00a0que \u00a0 \u00a0el \u00a0 \u00a0\u201cverdadero \u00a0proceso\u201d \u00a0se \u00a0inicia \u00a0en \u00a0la \u00a0Sala \u00a0cuando acepta la \u00a0documentaci\u00f3n \u00a0 y \u00a0 \u201cabre \u00a0el \u00a0proceso\u201d. \u00a0\u00a0<\/p>\n<p>Dice \u00a0que \u00a0apoyado en esa tesis, no present\u00f3 \u00a0ninguna \u00a0objeci\u00f3n \u00a0a la legalizaci\u00f3n de la documentaci\u00f3n, m\u00e1xime que tampoco \u00a0se \u00a0le dio la oportunidad procesal para ello, raz\u00f3n por la cual advierte que el \u00a0diligenciamiento \u00a0se \u00a0encuentra \u00a0incompleto, \u00a0siendo, \u00a0por \u00a0tanto, \u00a0la \u00a0Corte la \u00a0entidad \u00a0que \u00a0le \u00a0corresponde \u00a0examinarlo formalmente y ordenar su devoluci\u00f3n a \u00a0los \u00a0citados \u00a0ministerios, \u00a0\u201ccon el objeto de obtener \u00a0el \u00a0perfeccionamiento \u00a0del \u00a0mismo, o conceptuar desfavorablemente por violaci\u00f3n \u00a0de los requisitos formales\u201d. \u00a0\u00a0<\/p>\n<p>3.5. \u00a0 En \u00a0 el \u00a0 cap\u00edtulo \u00a0 que \u00a0 titula \u00a0\u201cCONCEPTO \u00a0 \u00a0DEL \u00a0 \u00a0MINISTERIO \u00a0 \u00a0DE \u00a0 \u00a0RELACIONES \u00a0EXTERIORES\u201d, \u00a0sostiene \u00a0que el mismo no se encuentra \u00a0cabalmente \u00a0incorporado \u00a0en el diligenciamiento, raz\u00f3n por la cual se impone su \u00a0devoluci\u00f3n \u00a0 \u00a0\u201co \u00a0 posteriormente \u00a0 el \u00a0 concepto \u00a0desfavorable \u00a0por no encontrar debidamente cumplido el art\u00edculo 552 del C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal\u201d, \u00a0ya que no fue emitido de \u00a0manera \u00a0t\u00e9cnica \u00a0al no haberse certificado sobre la existencia o no de tratados \u00a0internacionales \u00a0 \u00a0 vigentes \u00a0 \u00a0con \u00a0 \u00a0el \u00a0 \u00a0pa\u00eds \u00a0 \u00a0requirente \u00a0 \u00a0de \u00a0 \u00a0manera \u00a0razonada. \u00a0\u00a0<\/p>\n<p>Asevera que el escrito allegado como concepto \u00a0no \u00a0cumple con ese requisito, al no estar motivado \u201cy \u00a0recorrer \u00a0todo \u00a0el \u00a0camino que el campo del derecho abarca en el momento y en el \u00a0aspecto del cual trata el concepto\u201d. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0expuesto, \u00a0pide que el expediente se \u00a0devuelva \u00a0 al \u00a0 Ministerio \u00a0 de \u00a0 Relaciones \u00a0 Exteriores \u00a0para \u00a0que \u00a0emita \u00a0uno \u00a0\u201ct\u00e9cnico \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0jur\u00eddico\u201d. \u00a0\u00a0<\/p>\n<p>A \u00a0continuaci\u00f3n sostiene que tiene entendido \u00a0que \u00a0entre \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica \u00a0y \u00a0Colombia existen instrumentos \u00a0internacionales. \u00a0Tales \u00a0son: \u00a0el \u00a0tratado bilateral de 1979, celebrado el 14 de \u00a0septiembre \u00a0de \u00a0ese \u00a0a\u00f1o \u00a0y aprobado mediante la Ley 27 de 1980 \u201cy \u00a0con canje de instrumentos de ratificaci\u00f3n seg\u00fan acta firmada en \u00a0Bogot\u00e1 \u00a0el 4 de marzo de 1982\u201d, la que fue declarada \u00a0inconstitucional, \u00a0por \u00a0lo \u00a0que \u00a0recuperaron \u00a0plena \u00a0vigencia, de acuerdo con la \u00a0pac\u00edfica \u00a0jurisprudencia \u00a0de \u00a0la \u00a0Corte, \u00a0las \u00a0leyes 606 de 1888 y 8\u00aa de 1943, \u00a0preceptivas \u00a0 que \u00a0 aprobaron \u00a0la \u00a0Convenci\u00f3n \u00a0de \u00a0Extradici\u00f3n \u00a0Rec\u00edproca \u00a0de \u00a0Delincuentes \u00a0 de \u00a0 1888 \u00a0 y \u00a0 su \u00a0 modificaci\u00f3n; \u00a0 la \u00a0Convenci\u00f3n \u00a0\u00danica \u00a0de \u00a0Estupefacientes \u00a0de \u00a01961; \u00a0la \u00a0Convenci\u00f3n \u00a0sobre Sustancias Psicotr\u00f3picas; la \u00a0Convenci\u00f3n \u00a0de \u00a0Naciones Unidas sobre el Tr\u00e1fico Il\u00edcito de Estupefacientes y \u00a0Sustancias \u00a0Psicotr\u00f3picas \u00a0de \u00a01988 \u00a0y el Tratado Multilateral de Montevideo de \u00a01993. \u00a0\u00a0<\/p>\n<p>En consecuencia, considera que como quiera que \u00a0entre \u00a0los \u00a0citados \u00a0Gobiernos \u00a0existen \u00a0tratados, \u00a0se \u00a0hace \u00a0necesario \u00a0que \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores \u00a0\u201cle explique \u00a0racionalmente \u00a0a \u00a0la \u00a0Corte \u00a0y \u00a0a la defensa la raz\u00f3n por la cual debe rituarse \u00a0este \u00a0 tr\u00e1mite \u00a0 de \u00a0 extradici\u00f3n \u00a0por \u00a0las \u00a0normas \u00a0comunes \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento Penal\u201d. \u00a0\u00a0<\/p>\n<p>3.6. \u00a0 En \u00a0 el \u00a0 ac\u00e1pite \u00a0 \u201cRECIPROCIDAD\u201d, dice que es imperioso que \u00a0mediante \u00a0la \u00a0respectiva \u00a0nota \u00a0Diplom\u00e1tica \u00a0enviada \u00a0a \u00a0las autoridades de los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica, \u00a0se \u00a0ordene \u00a0al \u00a0Estado \u00a0requirente \u00a0reconocer la \u00a0reciprocidad, \u00a0con \u00a0el \u00a0objeto de que\u00a0 el expediente sea perfeccionado, tal \u00a0como \u00a0lo \u00a0ordenan \u00a0los \u00a0art\u00edculos 9\u00b0 y 226 de la Constituci\u00f3n Pol\u00edtica, cuya \u00a0aplicaci\u00f3n \u00a0complementa \u00a0el \u00a0art\u00edculo \u00a0551 del C\u00f3digo de Procedimiento Penal, \u00a0\u201ccomo \u00a0un \u00a0requisito para perfeccionar el expediente \u00a0relativo a la extradici\u00f3n\u201d. \u00a0\u00a0<\/p>\n<p>A\u00f1ade: \u00a0<\/p>\n<p>\u201cEl tr\u00e1mite de extradici\u00f3n debe analizarse \u00a0como \u00a0un \u00a0conjunto \u00a0en \u00a0sus normas y por ello es totalmente legal que la defensa \u00a0haga \u00a0referencia \u00a0a \u00a0este \u00a0principio \u00a0del derecho internacional, ya que el mismo \u00a0art\u00edculo \u00a0552 \u00a0se \u00a0refiere \u00a0a \u00a0los \u00a0usos internacionales a los cuales el se\u00f1or \u00a0Ministro \u00a0de \u00a0Relaciones \u00a0Exteriores, \u00a0doctor \u00a0GUILLERMO \u00a0FERN\u00c1NDEZ DE SOTO, en \u00a0oficio \u00a0dirigido \u00a0al \u00a0Senado de la Rep\u00fablica, con fecha 6 de diciembre de 1999, \u00a0se \u00a0refiere \u00a0a \u00a0\u2018costumbres \u00a0internacionales\u2019 \u00a0y si la \u00a0Constituci\u00f3n \u00a0fundamenta las relaciones internacionales en este principio de la \u00a0reciprocidad, \u00a0mal \u00a0puede \u00a0el Ministerio de Relaciones Exteriores, el Ministerio \u00a0de \u00a0Justicia \u00a0y a\u00fan la Corte Suprema de Justicia desconocer, dentro del proceso \u00a0de \u00a0extradici\u00f3n \u00a0este \u00a0compromiso \u00a0que \u00a0es \u00a0pieza fundamental tanto para que la \u00a0Corte \u00a0emita, \u00a0en \u00a0pleno \u00a0derecho, \u00a0su \u00a0concepto \u00a0como para que la defensa puede \u00a0ejercitarse en debida forma\u201d. \u00a0\u00a0<\/p>\n<p>Agrega que dicho compromiso de reciprocidad es \u00a0obligatorio, \u00a0cuando \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones Exteriores advirti\u00f3 que no \u00a0existe \u00a0tratado \u00a0aplicable al presente tr\u00e1mite, y que como al Gobierno Nacional \u00a0le \u00a0corresponde \u00a0manejar las relaciones internacionales, est\u00e1 en la obligaci\u00f3n \u00a0de \u00a0aplicar \u00a0los principios que las rigen, raz\u00f3n por la cual ignora los motivos \u00a0que \u00a0se \u00a0tuvieron \u00a0para \u00a0obviar \u00a0la aplicaci\u00f3n del postulado de reciprocidad en \u00a0este tr\u00e1mite. \u00a0\u00a0<\/p>\n<p>Manifiesta \u00a0que \u00a0no \u00a0puede \u00a0alegarse \u00a0que \u00a0el \u00a0art\u00edculo \u00a0 35 \u00a0 de \u00a0 la \u00a0Constituci\u00f3n \u00a0Pol\u00edtica \u00a0no \u00a0exija \u00a0el \u00a0principio \u00a0de \u00a0reciprocidad, \u00a0ya que el art\u00edculo 226 ibidem, que constituye un mandato general \u00a0para \u00a0las relaciones internacionales, complementa la primera de las preceptivas, \u00a0lo \u00a0que \u00a0lleva \u00a0a \u00a0concluir \u00a0que \u00a0dicho postulado s\u00ed debe aplicarse al presente \u00a0asunto. Id\u00e9ntico alcance le otorga al art\u00edculo 9\u00b0 de la Carta. \u00a0\u00a0<\/p>\n<p>3.7. \u00a0En \u00a0el \u00a0cap\u00edtulo \u00a0que \u00a0denomina de las \u00a0\u201cPRUEBAS\u201d, \u00a0advierte que \u00a0como \u00a0 \u00a0 existen \u00a0 \u00a0muchas \u00a0 \u00a0\u201crazones\u201d \u00a0para \u00a0no \u00a0devolver el diligenciamiento\u00a0 a los multicitados \u00a0Ministerios \u00a0y \u00a0as\u00ed \u00a0se \u00a0perfeccione, conforme lo dispone la Constituci\u00f3n y la \u00a0ley, \u00a0como \u00a0lo \u00a0ha \u00a0entendido \u00a0la Corte, solicita la pr\u00e1ctica de las siguientes \u00a0probanzas: \u00a0\u00a0<\/p>\n<p>3.7.1.\u00a0 \u00a0En \u00a0el \u00a0cap\u00edtulo \u00a0que \u00a0titula \u00a0\u201cPRUEBAS PARA COMPLEMENTAR EL EXPEDIENTE Y QUE DEBEN \u00a0SER \u00a0 REMITIDAS \u00a0 POR \u00a0 EL \u00a0 ESTADO \u00a0 REQUIRENTE, \u00a0 ESTADOS \u00a0 UNIDOS\u201d, pide las siguientes: \u00a0\u00a0<\/p>\n<p>3.7.1.1. Que a trav\u00e9s de la v\u00eda diplom\u00e1tica \u00a0se \u00a0solicite \u00a0a \u00a0las \u00a0autoridades competentes de los Estados Unidos de Am\u00e9rica, \u00a0que \u00a0especifiquen, \u00a0en forma clara y precisa, las circunstancias de tiempo, modo \u00a0y \u00a0lugar \u00a0en \u00a0que \u00a0ocurrieron los hechos, as\u00ed como tambi\u00e9n las personas que en \u00a0ellas \u00a0intervinieron. \u00a0As\u00ed \u00a0mismo, \u00a0dir\u00e1n \u00a0si \u201chubo \u00a0incautaci\u00f3n \u00a0de \u00a0elementos, \u00a0allegando \u00a0copias \u00a0de \u00a0las \u00a0actas \u00a0respectivas; se \u00a0indicar\u00e1 \u00a0en forma clara y precisa las autoridades y personas que intervinieron \u00a0en el procedimiento de cada hecho\u201d. \u00a0\u00a0<\/p>\n<p>Tambi\u00e9n \u00a0pide que se solicite la copia de la \u00a0prueba \u00a0t\u00e9cnica \u00a0que \u00a0demuestre \u00a0la \u00a0calidad de la sustancia incautada y de los \u00a0testimonios \u00a0que apoyan cada hecho, pues, respecto a estos \u00faltimos, se pretende \u00a0hacer \u00a0valer \u00a0en \u00a0este \u00a0tr\u00e1mite, \u00a0aquellos \u00a0que, a su juicio, no tienen ning\u00fan \u00a0valor en el Estado requirente. \u00a0\u00a0<\/p>\n<p>3.7.1.2. Que a trav\u00e9s de la v\u00eda diplom\u00e1tica \u00a0se \u00a0solicite \u00a0a \u00a0la autoridad correspondiente de los Estados Unidos de Am\u00e9rica, \u00a0suministre \u00a0el \u00a0nombre \u00a0del \u00a0defensor, contractual o de oficio, que ha tenido su \u00a0representado \u00a0dentro \u00a0del \u00a0proceso \u00a0radicado \u00a0bajo el n\u00famero 99-6153-CR-RYSKAMP \u00a0(s)(s)(s)(s), \u00a0el \u00a0que cursa en la Corte Distrital de los Estados Unidos para el \u00a0Distrito Sur de Florida, Divisi\u00f3n del Fort Lauderdale. \u00a0\u00a0<\/p>\n<p>3.7.1.3. Que a trav\u00e9s de la v\u00eda diplom\u00e1tica \u00a0se \u00a0solicite \u00a0a \u00a0las autoridades de los Estados Unidos que informen qu\u00e9 pruebas \u00a0ha \u00a0solicitado \u00a0el defensor, \u201caportando en lo posible \u00a0los \u00a0actos \u00a0que \u00a0en \u00a0este \u00a0sentido \u00a0se \u00a0hayan \u00a0hecho \u00a0y \u00a0sus \u00a0resultados ante la \u00a0Corte\u201d. \u00a0\u00a0<\/p>\n<p>3.7.1.4. Que a trav\u00e9s de la v\u00eda diplom\u00e1tica \u00a0se \u00a0le \u00a0solicite al fiscal que conoce del caso en la Corte de los Estados Unidos \u00a0de \u00a0 Am\u00e9rica, \u00a0informe \u00a0las \u00a0razones \u00a0que \u00a0tuvo \u00a0para \u00a0dar \u00a0por \u00a0demostrada \u00a0la \u00a0responsabilidad \u00a0o \u00a0el \u00a0dolo \u00a0de \u00a0Santiago \u00a0V\u00e9lez Vel\u00e1squez en cada uno de los \u00a0cargos \u00a0formulados \u00a0en \u00a0su \u00a0contra, \u00a0toda \u00a0vez \u00a0que \u00a0los documentos allegados no \u00a0cuentan \u00a0con \u00a0medios \u00a0de \u00a0pruebas, \u00a0y as\u00ed mismo que se complemente, para que la \u00a0Corte \u00a0 pueda \u00a0 conceptuar \u00a0sobre \u00a0la \u00a0equivalencia \u00a0o \u00a0no \u00a0del \u00a0\u201cacto aportado\u201d. \u00a0\u00a0<\/p>\n<p>Manifiesta \u00a0que \u00a0las probanzas en precedencia \u00a0rese\u00f1adas \u00a0son \u00a0procedentes \u00a0y \u00a0conducentes, \u00a0pues \u00a0con \u00a0las \u00a0mismas \u00a0se \u00a0busca \u00a0complementar \u00a0la \u00a0documentaci\u00f3n \u00a0y \u00a0reunir \u00a0los \u00a0requisitos \u00a0b\u00e1sicos que exige \u00a0nuestra \u00a0resoluci\u00f3n de acusaci\u00f3n, la que \u201cgarantiza \u00a0el \u00a0leg\u00edtimo \u00a0derecho \u00a0a \u00a0la \u00a0defensa \u00a0que \u00a0se ve entorpecido con el indictment \u00a0aportado\u201d. \u00a0\u00a0<\/p>\n<p>3.7.2. \u00a0 En \u00a0 la \u00a0secci\u00f3n \u00a0\u201cPRUEBAS \u00a0PARA \u00a0COMPLEMENTAR EL CONCEPTO DEL MINISTERIO DE RELACIONES \u00a0EXTERIORES\u201d impetra las siguientes: \u00a0\u00a0<\/p>\n<p>3.7.2.1. \u00a0Que \u00a0se \u00a0solicite \u00a0al Ministerio de \u00a0Relaciones \u00a0Exteriores \u00a0que \u00a0remita \u00a0copias \u00a0de \u00a0la \u00a0Convenci\u00f3n de Extradici\u00f3n \u00a0suscrita \u00a0entre Colombia y los Estados Unidos de Am\u00e9rica, el 6 de mayo de 1888, \u00a0la \u00a0que \u00a0fue \u00a0aprobada \u00a0por \u00a0la ley 66 del mismo a\u00f1o,\u00a0 y de la Convenci\u00f3n \u00a0Supletoria, \u00a0tambi\u00e9n \u00a0suscrita entre estos Estados, el 9 de septiembre de 1940, \u00a0aprobada \u00a0por \u00a0la \u00a0ley \u00a08 \u00a0de \u00a01943. \u00a0As\u00ed \u00a0mismo, \u00a0que \u00a0se certifique si dichos \u00a0Convenios \u00a0se encuentran vigentes o no. En caso negativo, informar\u00e1 las razones \u00a0por las cuales no rigen y el d\u00eda en que termin\u00f3 su vigencia. \u00a0\u00a0<\/p>\n<p>3.7.2.2. \u00a0Que \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores \u00a0remita \u00a0copia de la Convenci\u00f3n sobre Extradici\u00f3n de Montevideo del \u00a026 \u00a0de \u00a0diciembre \u00a0de \u00a01933, \u00a0de \u00a0la Convenci\u00f3n \u00danica sobre Estupefacientes de \u00a01961, \u00a0 del \u00a0 Protocolo \u00a0 de \u00a0 Modificaci\u00f3n \u00a0de \u00a0la \u00a0Convenci\u00f3n \u00a0\u00danica \u00a0sobre \u00a0Estupefacientes, \u00a0del Tratado de Extradici\u00f3n de 1979, suscrito entre Colombia y \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica, \u00a0y \u00a0de la Convenci\u00f3n de las Naciones Unidas \u00a0contra \u00a0el \u00a0Tr\u00e1fico \u00a0Il\u00edcito \u00a0de Estupefacientes y Sustancias Sicotr\u00f3picas de \u00a01988. \u00a0As\u00ed \u00a0mismo, \u00a0indicar\u00e1 si los mismos fueron aprobados por Colombia y los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica, \u00a0se\u00f1alando las fechas de dep\u00f3sito de las normas \u00a0aprobatorias. \u00a0Igualmente, \u00a0informar\u00e1 \u00a0si alguno de los Estados hizo reservas o \u00a0declaraciones \u00a0en \u00a0torno \u00a0a \u00a0los citados tratados, allegando la respectiva copia \u00a0del documento. \u00a0\u00a0<\/p>\n<p>Por \u00a0su \u00a0parte, \u00a0el \u00a0Ministerio de Relaciones \u00a0Exteriores \u00a0certificar\u00e1 \u00a0si los mismos se encuentran vigentes para Colombia. En \u00a0caso \u00a0negativo, \u00a0informar\u00e1 las razones por las cuales no rigen y el d\u00eda en que \u00a0termin\u00f3 \u00a0su \u00a0vigencia. \u00a0Igual \u00a0cometido \u00a0cumplir\u00e1 \u00a0el \u00a0Gobierno de los Estados \u00a0Unidos de Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>3.7.2.3. \u00a0Que \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores \u00a0remita \u00a0copia \u00a0del oficio fechado el 6 de diciembre de 1999, emanado \u00a0del \u00a0despacho \u00a0del \u00a0Ministro \u00a0y \u00a0dirigido \u00a0al Secretario General de la Comisi\u00f3n \u00a0Segunda del\u00a0 Senado de la Rep\u00fablica. \u00a0\u00a0<\/p>\n<p>Asegura \u00a0que \u00a0las \u00a0anteriores \u00a0pruebas \u00a0son \u00a0pertinentes \u00a0 y \u00a0 conducentes, \u00a0 en \u00a0raz\u00f3n \u00a0a \u00a0que \u00a0con \u00a0ellas \u00a0\u201cse \u00a0har\u00e1 \u00a0el \u00a0estudio \u00a0completo en relaci\u00f3n con el procedimiento a \u00a0seguir \u00a0 en \u00a0 el \u00a0 tr\u00e1mite \u00a0 de \u00a0 la \u00a0 Corte \u00a0Suprema \u00a0de \u00a0Justicia\u201d, \u00a0a \u00a0fin \u00a0de determinar cient\u00edfica y jur\u00eddicamente si Colombia \u00a0tiene \u00a0tratados \u00a0vigentes \u00a0de \u00a0extradici\u00f3n \u00a0con \u00a0los Estados Unidos de Am\u00e9rica \u00a0\u201co si por el contrario no existen estos instrumentos \u00a0y, \u00a0entonces, \u00a0deba \u00a0procederse \u00a0a la tramitaci\u00f3n por las normas ordinarias del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal\u201d. \u00a0A\u00f1ade \u00a0que con \u00a0tales \u00a0medios \u00a0de \u00a0prueba \u00a0se \u00a0podr\u00e1 \u00a0ejercer, \u00a0en \u00a0debida \u00a0forma, \u00a0la \u00a0defensa \u00a0t\u00e9cnica. \u00a0\u00a0<\/p>\n<p>3.7.2.4. \u00a0Que \u00a0se \u00a0solicite \u00a0al Ministerio de \u00a0Relaciones \u00a0Exteriores que remita copia del acta o el compromiso de reciprocidad \u00a0de \u00a0extradici\u00f3n \u00a0de extranjeros o nacionales por parte de los Estados Unidos de \u00a0Am\u00e9rica, \u00a0tal \u00a0como \u00a0lo \u00a0imponen \u00a0los \u00a0art\u00edculos 9\u00b0 y 226 de la Constituci\u00f3n \u00a0Pol\u00edtica. \u00a0\u00a0<\/p>\n<p>Agrega \u00a0que \u00a0en \u00a0caso \u00a0de que no existan esos \u00a0documentos, \u00a0el citado Ministerio certificar\u00e1 las razones de hecho y de derecho \u00a0que \u00a0tuvo \u00a0para \u00a0no dar cumplimiento a los mencionados art\u00edculos de la Carta de \u00a0Derechos. \u00a0Anota \u00a0que \u00a0con \u00a0dicho \u00a0elemento de juicio se complementar\u00e1 en forma \u00a0legal \u00a0el \u00a0diligenciamiento \u00a0y \u00a0que \u00a0pretende \u00a0demostrar \u00a0que \u00a0no existe con los \u00a0Estados Unidos de Am\u00e9rica un compromiso de reciprocidad. \u00a0\u00a0<\/p>\n<p>3.7.2.5. \u00a0Que \u00a0se \u00a0solicite \u00a0al Ministerio de \u00a0Relaciones \u00a0Exteriores, al Ministerio de Justicia y del Derecho y a la Fiscal\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0remitan las listas de las solicitudes de extradici\u00f3n \u00a0que \u00a0Colombia \u00a0ha \u00a0elevado, \u00a0a \u00a0partir \u00a0de \u00a01980 \u00a0y 1992 para la \u00faltima entidad \u00a0citada, \u00a0a \u00a0los Estados Unidos de Am\u00e9rica, tanto de nacionales colombianos como \u00a0de \u00a0extranjeros. \u00a0Tambi\u00e9n \u00a0pide \u00a0que \u00a0se \u00a0alleguen \u00a0las \u00a0correspondientes Notas \u00a0Verbales, \u00a0debidamente \u00a0traducidas, \u00a0y \u00a0que \u00a0se especifique si las mismas fueron \u00a0atendidas \u00a0o rechazadas. \u201cSi no han sido respondidas, \u00a0el \u00a0Ministerio \u00a0de Relaciones Exteriores certificar\u00e1 las razones por los cuales \u00a0los \u00a0Estados \u00a0Unidos de Am\u00e9rica no hayan respondido dicha solicitud\u201d. \u00a0\u00a0<\/p>\n<p>Afirma \u00a0que \u00a0esta \u00a0prueba \u00a0es \u00a0conducente \u00a0y \u00a0pertinente \u00a0para \u00a0establecer si se ha cumplido con el principio de reciprocidad, \u00a0al \u00a0 tenor \u00a0 de \u00a0 lo \u00a0 dispuesto \u00a0 en \u00a0el \u00a0art\u00edculo \u00a04\u00b0 \u00a0de \u00a0la \u00a0Constituci\u00f3n \u00a0Pol\u00edtica. \u00a0\u00a0<\/p>\n<p>3.7.3 \u00a0 En \u00a0 el \u00a0 ac\u00e1pite \u00a0 que \u00a0 titul\u00f3 \u00a0\u201cPRUEBAS \u00a0RELACIONADAS \u00a0CON \u00a0EL \u00a0ART\u00cdCULO \u00a0551 \u00a0DEL \u00a0C\u00d3DIGO \u00a0 DE \u00a0 PROCEDIMIENTO \u00a0 PENAL\u201d, \u00a0 pide \u00a0 las \u00a0siguientes: \u00a0\u00a0<\/p>\n<p>3.7.3.1. Que a trav\u00e9s de la v\u00eda diplom\u00e1tica \u00a0se \u00a0solicite \u00a0a \u00a0las \u00a0autoridades \u00a0correspondientes \u00a0de \u00a0los \u00a0Estados \u00a0Unidos de \u00a0Am\u00e9rica, \u00a0remitan \u00a0las traducciones, debidamente autenticadas, del T\u00edtulo 178, \u00a0Cap\u00edtulo \u00a0209,\u00a0 \u00a0Secciones \u00a0del \u00a03181 al 3196 del C\u00f3digo de Procedimiento \u00a0Federal, \u00a0 por \u00a0cuanto \u00a0fueron \u00a0relacionadas \u00a0en \u00a0el \u00a0proceso \u00a0de \u00a0extradici\u00f3n. \u00a0Igualmente, \u00a0que \u00a0se \u00a0aporte la \u201cCOPIA DE LA SECCI\u00d3N \u00a09-15-100 \u00a0del \u00a0Manual \u00a0de \u00a0los \u00a0Fiscales de los Estados Unidos\u00a0 expedido en \u00a01988\u201d. \u00a0\u00a0<\/p>\n<p>Sostiene que la citada prueba es pertinente y \u00a0conducente, \u00a0por \u00a0cuanto la Sala debe estudiar la normativa para verificar si se \u00a0cumplen \u00a0 los \u00a0 requisitos \u00a0 legales, \u00a0caso \u00a0contrario \u00a0no \u00a0tendr\u00eda \u00a0las \u00a0bases \u00a0suficientes \u00a0 para \u00a0 emitir \u00a0el \u00a0concepto \u00a0de \u00a0manera \u00a0jur\u00eddica, \u00a0consciente \u00a0y \u00a0cient\u00edfica. \u00a0\u00a0<\/p>\n<p>3.7.3.2. Que a trav\u00e9s de la v\u00eda diplom\u00e1tica \u00a0se \u00a0solicite \u00a0a \u00a0las \u00a0autoridades \u00a0correspondientes \u00a0de \u00a0los \u00a0Estados \u00a0Unidos de \u00a0Am\u00e9rica, \u00a0aporten al tr\u00e1mite, debidamente autenticadas y traducidas, la Ley de \u00a0Extradici\u00f3n \u00a0de \u00a01982 \u00a0y \u00a0de la Ley de Interpretaci\u00f3n\u00a0 de los Tratados de \u00a0Extradici\u00f3n del mismo a\u00f1o. \u00a0\u00a0<\/p>\n<p>Sostiene \u00a0que \u00a0la \u00a0citada \u00a0prueba tambi\u00e9n es \u00a0conducente y pertinente por las razones expuestas en precedencia. \u00a0\u00a0<\/p>\n<p>3.7.3.3. \u00a0Que \u00a0se \u00a0solicite \u00a0al Ministerio de \u00a0Relaciones \u00a0Exteriores \u00a0que pida, a trav\u00e9s de la v\u00eda diplom\u00e1tica, al Gobierno \u00a0de \u00a0los Estados Unidos, debidamente traducida, copia del manual de instrucciones \u00a0que \u00a0 el \u00a0 \u201cjuez \u00a0tiene \u00a0la \u00a0obligaci\u00f3n \u00a0 de \u00a0 dar \u00a0 a \u00a0los \u00a0jurados \u00a0en \u00a0causas \u00a0criminales, \u00a0 para \u00a0 las \u00a0 Cortes \u00a0 Und\u00e9cimo \u00a0 Primer \u00a0 Circuito\u2026\u201d. \u00a0\u00a0<\/p>\n<p>Asevera \u00a0que la citada prueba es pertinente y \u00a0conducente, \u00a0por \u00a0cuanto la Sala debe estudiar la normativa para verificar si se \u00a0cumplen \u00a0 los \u00a0 requisitos \u00a0 legales, \u00a0caso \u00a0contrario \u00a0no \u00a0tendr\u00eda \u00a0las \u00a0bases \u00a0suficientes \u00a0 para \u00a0 emitir \u00a0el \u00a0concepto \u00a0de \u00a0manera \u00a0jur\u00eddica, \u00a0consciente \u00a0y \u00a0cient\u00edfica. \u00a0\u00a0<\/p>\n<p>3.7.3.4. \u00a0Que \u00a0se \u00a0solicite \u00a0al Ministerio de \u00a0Justicia \u00a0y \u00a0del \u00a0Derecho\u00a0 \u00a0certifique \u00a0y remita copia de la resoluci\u00f3n de \u00a0aceptaci\u00f3n \u00a0como \u00a0traductora oficial de ingl\u00e9s de la se\u00f1ora Sandra R. Acosta, \u00a0pues \u00a0ella \u00a0aparece certificando los documentos remitidos por los Estados Unidos \u00a0de Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>Manifiesta que la citada prueba es conducente, \u00a0pues \u00a0con ella se puede determinar la legalidad de la documentaci\u00f3n aportada al \u00a0tr\u00e1mite, \u00a0cuando, \u00a0a \u00a0su \u00a0juicio, no la re\u00fane, lo que dar\u00eda como consecuencia \u00a0que \u00a0no \u00a0se \u00a0pudiera \u00a0emitir el concepto y, consecuencialmente, se impondr\u00eda su \u00a0devoluci\u00f3n al lugar de origen. \u00a0\u00a0<\/p>\n<p>3.7.4. En el aparte que llama \u201cPRUEBAS \u00a0DE \u00a0LA FORMALIDAD DE LAS PRUEBAS OBETENIDAS POR LOS ESTADOS \u00a0UNIDOS \u00a0 \u00a0 EN \u00a0 \u00a0 COLOMBIA\u201d, \u00a0 \u00a0 solicita \u00a0 \u00a0 las \u00a0siguientes: \u00a0\u00a0<\/p>\n<p>3.7.4.1. \u00a0Que \u00a0la \u00a0Fiscal\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0como \u00a0el \u00a0organismo encargado de tramitar las peticiones de asistencia \u00a0judicial, \u00a0de \u00a0acuerdo \u00a0con la Convenci\u00f3n de Viena, remita los documentos sobre \u00a0la \u00a0presunta \u00a0solicitud de asistencia judicial elevada por los Estados Unidos de \u00a0Am\u00e9rica \u00a0 \u00a0 en \u00a0 \u00a0 la \u00a0 \u00a0 llamada \u00a0 \u00a0 \u201cOperaci\u00f3n \u00a0Milenio\u201d, \u00a0 la \u00a0 que \u00a0 arroj\u00f3 \u00a0la \u00a0captura \u00a0de \u00a0su \u00a0defendido. \u00a0\u00a0<\/p>\n<p>Sostiene \u00a0que \u00a0este \u00a0medio \u00a0de convicci\u00f3n es \u00a0pertinente, \u00a0ya \u00a0que \u00a0en \u00a0la \u00a0petici\u00f3n \u00a0de extradici\u00f3n se hace menci\u00f3n de tal \u00a0asistencia, \u00a0por \u00a0lo \u00a0que \u00a0la Corte lo requiere para cuando entre a calificar la \u00a0formalidad \u00a0legal \u00a0de \u00a0la \u00a0documentaci\u00f3n, \u00a0y \u00a0para \u00a0establecer \u00a0si se viol\u00f3 la \u00a0Constituci\u00f3n \u00a0y \u00a0la \u00a0ley, \u00a0\u201cen cuanto a que se haya \u00a0ofrecido \u00a0en \u00a0extradici\u00f3n a nacionales colombianos por nacimiento, sin el pleno \u00a0de \u00a0los \u00a0requisitos \u00a0constitucionales \u00a0y \u00a0legales, \u00a0extralimitando funciones por \u00a0parte de los funcionarios p\u00fablicos\u201d. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0dice pretender demostrar que en ese \u00a0procedimiento se avasall\u00f3 nuestro ordenamiento jur\u00eddico. \u00a0\u00a0<\/p>\n<p>3.7.4.2. \u00a0Que \u00a0se \u00a0solicite \u00a0a \u00a0la \u00a0Polic\u00eda \u00a0Nacional \u00a0remita \u00a0copia \u00a0de la documentaci\u00f3n relacionada con la \u201cOperaci\u00f3n \u00a0 Milenio\u201d, \u00a0ya \u00a0sea \u00a0de \u00a0esa \u00a0entidad o de otras. \u00a0\u00a0<\/p>\n<p>Estima que la prueba es pertinente, pues en la \u00a0documentaci\u00f3n \u00a0aportada por el Estado solicitante se hace menci\u00f3n a ese hecho, \u00a0por \u00a0lo \u00a0que \u00a0se \u00a0requiere \u00a0para \u00a0que \u00a0la \u00a0Corte \u00a0pueda emitir concepto sobre la \u00a0legalidad \u00a0 de \u00a0 los \u00a0instrumentos \u00a0y \u00a0si \u00a0se \u00a0viol\u00f3 \u00a0la \u00a0Ley, \u00a0\u201cen \u00a0cuanto \u00a0a \u00a0que \u00a0se \u00a0haya \u00a0ofrecido \u00a0en extradici\u00f3n a nacionales \u00a0colombianos \u00a0por \u00a0nacimiento, \u00a0sin el pleno de los requisitos constitucionales y \u00a0legales, \u00a0 \u00a0extralimitando \u00a0 \u00a0funciones \u00a0 \u00a0por \u00a0 parte \u00a0 de \u00a0 los \u00a0 funcionarios \u00a0p\u00fablicos\u201d. \u00a0\u00a0<\/p>\n<p>Agrega \u00a0que \u00a0pretende \u00a0demostrar \u00a0que \u00a0en ese \u00a0procedimiento se avasall\u00f3 nuestro ordenamiento jur\u00eddico. \u00a0\u00a0<\/p>\n<p>3.7.4.3. \u00a0Que solicite a la Polic\u00eda Nacional \u00a0informe, \u00a0de \u00a0manera \u00a0detallada, \u00a0la forma como se obtuvieron las grabaciones de \u00a0las \u00a0conversaciones \u00a0a que hace referencia\u00a0 el Agente de la D. E. A, se\u00f1or \u00a0Paul \u00a0K. \u00a0Craine, especificando los medios electr\u00f3nicos y los procedimientos de \u00a0inteligencia \u00a0utilizados, \u00a0\u201ccon el fin de determinar \u00a0los \u00a0asistentes \u00a0a las aludidas reuniones, aportando los documentos que permitan \u00a0la \u00a0identificaci\u00f3n \u00a0exacta \u00a0de \u00a0cada \u00a0uno \u00a0de \u00a0ellos \u00a0en \u00a0dicha \u00a0reuni\u00f3n. Debe \u00a0aportarse \u00a0 en \u00a0lo \u00a0posible \u00a0las \u00a0cintas \u00a0magnetof\u00f3nicas \u00a0usadas \u00a0o \u00a0copias \u00a0de \u00a0ellas\u201d. \u00a0\u00a0<\/p>\n<p>Asevera \u00a0que \u00a0la prueba es pertinente, ya que \u00a0guarda \u00a0dependencia \u00a0con la documentaci\u00f3n aportada y hace relaci\u00f3n a la manera \u00a0como \u00a0se \u00a0obtuvieron \u00a0dichas \u00a0conversaciones, pues se opone a lo estatuido en el \u00a0art\u00edculo \u00a029 \u00a0de \u00a0la Constituci\u00f3n Pol\u00edtica, en lo relativo a que el procesado \u00a0tiene \u00a0derecho de conocer las pruebas que contra \u00e9l se tengan. As\u00ed mismo, a su \u00a0juicio, \u00a0sirve para determinar la legalidad de los instrumentos y para verificar \u00a0si \u00a0se \u00a0viol\u00f3 \u00a0nuestro \u00a0ordenamiento \u00a0jur\u00eddico, \u201cen \u00a0cuanto \u00a0a \u00a0que \u00a0se \u00a0haya \u00a0ofrecido \u00a0en extradici\u00f3n a nacionales colombianos por \u00a0nacimiento, \u00a0 sin \u00a0el \u00a0pleno \u00a0de \u00a0los \u00a0requisitos \u00a0constitucionales \u00a0y \u00a0legales, \u00a0extralimitando \u00a0funciones \u00a0por \u00a0parte \u00a0de los funcionarios p\u00fablicos\u201d. \u00a0\u00a0<\/p>\n<p>3.7.4.4. \u00a0Que \u00a0se \u00a0solicite \u00a0a \u00a0la \u00a0Fiscal\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n \u00a0copia de las cintas que contengan las interceptaciones \u00a0telef\u00f3nicas \u00a0a \u00a0que \u00a0hace \u00a0referencia \u00a0el citado agente de la D. E. A., las que \u00a0presuntamente \u00a0fueron \u00a0entregadas \u00a0a las autoridades judiciales correspondientes \u00a0de los Estados Unidos de Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>Advierte \u00a0que, \u00a0por la razones en precedencia \u00a0indicadas, la prueba es pertinente. \u00a0\u00a0<\/p>\n<p>3.7.4.5. \u00a0Que \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores, \u00a0 previo \u00a0al \u00a0tr\u00e1mite \u00a0diplom\u00e1tico, \u00a0solicite \u00a0a \u00a0las \u00a0autoridades \u00a0correspondientes \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de Am\u00e9rica que alleguen las citadas \u00a0cintas \u00a0magnetof\u00f3nicas, \u00a0en las cuales presuntamente particip\u00f3 su patrocinado, \u00a0y \u00a0que \u00a0se \u00a0suministre \u201clas razones\u00a0 cr\u00edticas y \u00a0de \u00a0 ciencia \u00a0 criminal \u00a0 que \u00a0llevan \u00a0a \u00a0identificar \u00a0a \u00a0mi \u00a0defendido, \u00a0se\u00f1or \u00a0SANTIAGO \u00a0V\u00c9LEZ \u00a0VEL\u00c1SQUEZ, \u00a0como participante en ellas\u201d. \u00a0\u00a0<\/p>\n<p>Sostiene \u00a0que de los argumentos expuestos, se \u00a0infiere que la prueba es pertinente. \u00a0\u00a0<\/p>\n<p>3.7.5. \u00a0 En \u00a0 el \u00a0 cap\u00edtulo \u00a0 que \u00a0enuncia \u00a0\u201cPRUEBAS \u00a0 \u00a0DEL \u00a0 \u00a0PRINCIPIO \u00a0 \u00a0DE \u00a0 \u00a0LA \u00a0 \u00a0DOBLE \u00a0INCRIMINACI\u00d3N\u201d, \u00a0luego \u00a0de \u00a0afirmar \u00a0que los cargos \u00a0elevados \u00a0en \u00a0contra \u00a0de \u00a0su \u00a0defendido \u00a0por \u00a0las \u00a0autoridades judiciales de los \u00a0Estados \u00a0Unidos \u00a0de Am\u00e9rica, son por el delito de conspiraci\u00f3n, punible que, a \u00a0su \u00a0juicio, \u00a0no \u00a0se encuentra tipificado en nuestra legislaci\u00f3n penal, pide las \u00a0siguientes: \u00a0\u00a0<\/p>\n<p>3.7.5.1. \u00a0Que \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores, \u00a0previo al tr\u00e1mite diplom\u00e1tico, solicite a la Corte Suprema de los \u00a0Estados \u00a0Unidos de Am\u00e9rica que remita, debidamente traducida, la jurisprudencia \u00a0sobre los elementos constitutivos del delito de conspiraci\u00f3n. \u00a0\u00a0<\/p>\n<p>3.7.5.2.Que \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores, \u00a0previo \u00a0al tr\u00e1mite diplom\u00e1tico, solicite a las autoridades de los \u00a0Estados \u00a0 \u00a0Unidos \u00a0 \u00a0de \u00a0 Am\u00e9rica, \u00a0 debidamente \u00a0 traducido, \u00a0 \u201cel \u00a0manual \u00a0Devitt \u00a0de \u00a0pr\u00e1cticas \u00a0e \u00a0instrucciones\u00a0 al jurado \u00a0federal \u00a0denominado \u00a0\u2018MAUAL \u00a0E. \u00a0DEVITT \u00a0C. \u00a0BLACKMAR \u00a0FEDERAL \u00a0JURY \u00a0PRACTICE \u00a0AND \u00a0INSTRUCTIONS\u2019\u201d. \u00a0\u00a0<\/p>\n<p>Estima \u00a0 que \u00a0las \u00a0anteriores \u00a0pruebas \u00a0son \u00a0procedentes, \u00a0pues con ellas se trata de obtener material suficiente para que la \u00a0Corte \u00a0pueda \u00a0emitir el concepto desprovisto de toda apreciaci\u00f3n personal sobre \u00a0el \u00a0principio de la doble incriminaci\u00f3n. As\u00ed mismo, dice que tambi\u00e9n pretende \u00a0demostrar \u00a0que \u00a0no \u00a0existe \u00a0una relaci\u00f3n conceptual entre la conspiraci\u00f3n y el \u00a0concierto para delinquir. \u00a0\u00a0<\/p>\n<p>3.7.5.3. \u00a0Que \u00a0se \u00a0solicite \u00a0a \u00a0la \u00a0Academia \u00a0Colombiana \u00a0de \u00a0Jurisprudencia \u00a0certifique, \u00a0con la debida argumentaci\u00f3n, si el \u00a0delito \u00a0 de \u00a0conspiraci\u00f3n \u00a0es \u00a0equivalente \u00a0jur\u00eddicamente \u00a0con \u00a0el \u00a0delito \u00a0de \u00a0concierto para delinquir que contempla nuestra legislaci\u00f3n penal. \u00a0\u00a0<\/p>\n<p>Agrega \u00a0que \u00a0la \u00a0prueba \u00a0es procedente, pues, \u00a0adem\u00e1s \u00a0de \u00a0que pretende demostrar que no existe una relaci\u00f3n conceptual entre \u00a0la \u00a0conspiraci\u00f3n \u00a0y \u00a0el \u00a0concierto \u00a0para \u00a0delinquir, \u00a0est\u00e1 \u00a0relacionada con el \u00a0concepto que debe emitir la Sala. \u00a0\u00a0<\/p>\n<p>3.7.6. \u00a0En \u00a0el \u00a0aparte \u00a0que \u00a0denomina\u00a0 \u00a0\u201cPRUEBAS \u00a0 RELACIONADAS \u00a0CON \u00a0EL \u00a0REQUISITO \u00a0DE \u00a0LA \u00a0EQUIVALENCIA \u00a0DEL \u00a0ACTO \u00a0EXTRANJERO CON LA RESOLUCI\u00d3N DE ACUSACI\u00d3N\u201d, eleva las siguientes: \u00a0\u00a0<\/p>\n<p>3.7.6.1. \u00a0Que \u00a0se \u00a0ordene \u00a0el traslado a este \u00a0tr\u00e1mite \u00a0de las diligencias que contiene el expediente radicado bajo el n\u00famero \u00a06362, \u00a0el \u00a0que \u00a0se \u00a0encuentra \u00a0en la Secretar\u00eda de los Jueces Especializados de \u00a0Bogot\u00e1, \u00a0esto es, la declaraci\u00f3n del Abogado Joel Rosenthal, quien detalla los \u00a0requisitos \u00a0y \u00a0dem\u00e1s \u00a0valores \u00a0jur\u00eddicos \u00a0que debe contener el indictment y la \u00a0traducci\u00f3n \u00a0oficial \u00a0del C\u00f3digo Federal, tambi\u00e9n referido con la citada pieza \u00a0procesal. \u00a0\u00a0<\/p>\n<p>3.7.6.2. \u00a0Que \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores, \u00a0 previo \u00a0al \u00a0tr\u00e1mite \u00a0diplom\u00e1tico, \u00a0solicite \u00a0a \u00a0las \u00a0autoridades \u00a0correspondientes \u00a0de \u00a0los Estados Unidos de Am\u00e9rica copia de la sentencia de la \u00a0Corte \u00a0Suprema \u00a0de \u00a0Justicia \u00a0fechada \u00a0el 21 de mayo de 1992, dictada en el caso \u00a0Norton \u00a0Antony \u00a0Russell \u00a0y otros vs. Estados Unidos, dentro del radicado n\u00famero \u00a08-12.128. \u00a0\u00a0<\/p>\n<p>Acota que las citadas pruebas son pertinentes, \u00a0por \u00a0cuanto \u00a0que, \u00a0adem\u00e1s \u00a0de tratarse de documentos que legalmente obran en un \u00a0proceso \u00a0en \u00a0Colombia, la Corte puede emitir el concepto con base en la realidad \u00a0jur\u00eddica \u00a0 y \u00a0 no \u00a0 en \u00a0opiniones \u00a0personales, \u00a0al \u00a0estar \u00a0ilustrada \u00a0sobre \u00a0el \u00a0tema. \u00a0\u00a0<\/p>\n<p>3.7.6.3. \u00a0Que \u00a0el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores, \u00a0previo \u00a0al \u00a0tr\u00e1mite \u00a0diplom\u00e1tico, \u00a0solicite a la Corte Suprema de \u00a0Justicia \u00a0de los Estados Unidos de Am\u00e9rica, remita copias de tres sentencias en \u00a0las \u00a0que \u00a0se determinen los requisitos formales y sustanciales que debe contener \u00a0el indictment. \u00a0\u00a0<\/p>\n<p>Sostiene \u00a0que \u00a0la prueba es\u00a0 pertinente, \u00a0por \u00a0cuanto \u00a0que \u00a0la Corte as\u00ed puede emitir el concepto con base en la realidad \u00a0jur\u00eddica \u00a0 y \u00a0 no \u00a0 en \u00a0opiniones \u00a0personales, \u00a0al \u00a0estar \u00a0ilustrada \u00a0sobre \u00a0el \u00a0tema. \u00a0\u00a0<\/p>\n<p>3.7.6.4. \u00a0Que \u00a0se \u00a0solicite \u00a0a \u00a0la \u00a0Academia \u00a0Colombiana \u00a0 de \u00a0 Jurisprudencia\u00a0 \u00a0 concept\u00fae \u00a0 si \u00a0el \u00a0indictment \u00a0guarda \u00a0equivalencia \u00a0 con \u00a0 la \u00a0 resoluci\u00f3n \u00a0 de \u00a0 acusaci\u00f3n \u00a0que \u00a0contempla \u00a0nuestra \u00a0legislaci\u00f3n procesal. \u00a0\u00a0<\/p>\n<p>Asegura que la prueba es pertinente, toda vez \u00a0que \u00a0con \u00a0los \u00a0dem\u00e1s elementos de juicios impetrados en este cap\u00edtulo, la Sala \u00a0pueda \u00a0tener \u00a0fundamentos doctrinales para emitir un juicio en derecho, pues, en \u00a0su \u00a0criterio, \u00a0no \u00a0existe \u00a0equivalencia \u00a0entre el indictment y la resoluci\u00f3n de \u00a0acusaci\u00f3n. \u00a0\u00a0<\/p>\n<p>3.7.6.5. \u00a0Que \u00a0se \u00a0escuche en testimonio a un \u00a0auxiliar \u00a0de \u00a0la justicia experto en leyes de los Estados Unidos de Am\u00e9rica, de \u00a0acuerdo \u00a0con \u00a0las \u00a0listas \u00a0que \u00a0reposan \u00a0en \u00a0esta \u00a0Corporaci\u00f3n o en el Tribunal \u00a0Superior \u00a0 \u00a0de \u00a0 \u00a0Bogot\u00e1, \u00a0 \u00a0para \u00a0 \u00a0que \u00a0 \u00a0pueda \u00a0 ejercer \u00a0 el \u00a0 derecho \u00a0 de \u00a0contrainterrogar. \u00a0\u00a0<\/p>\n<p>Sugiere a los doctores Rodolfo Barrero Borr\u00e1s \u00a0o \u00a0a \u00a0Graciela \u00a0Vizcaya, \u00a0esta \u00a0\u00faltima \u00a0reconocida \u00a0en \u00a0los \u00a0Estados \u00a0Unidos de \u00a0Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>Asevera que con la prueba pretende que la Sala \u00a0tenga \u00a0conocimiento \u00a0directo y personal respecto de las instituciones jur\u00eddicas \u00a0del \u00a0pa\u00eds \u00a0requirente, \u00a0\u201cy \u00a0puedan \u00a0preguntar sobre \u00a0cualquier \u00a0duda \u00a0o \u00a0vac\u00edo \u00a0que puedan tener y ser debidamente ilustrados por un \u00a0conocedor \u00a0en \u00a0dichos \u00a0estatutos \u00a0y \u00a0as\u00ed \u00a0puedan \u00a0en forma plena y a conciencia \u00a0emitir \u00a0 un \u00a0 concepto \u00a0 fundamentado \u00a0 en \u00a0 la \u00a0realidad \u00a0jur\u00eddica\u201d. \u00a0\u00a0<\/p>\n<p>3.7.7. \u00a0 En \u00a0 el \u00a0 ac\u00e1pite \u00a0 que \u00a0 titula \u00a0\u201cPruebas \u00a0relacionadas \u00a0con \u00a0el \u00a0art\u00edculo \u00a0565 \u00a0del \u00a0C\u00f3digo \u00a0de Procedimiento Penal\u201d, despu\u00e9s de darle a \u00a0la \u00a0citada \u00a0preceptiva \u00a0su \u00a0personal interpretaci\u00f3n, dice que para demostrar la \u00a0existencia \u00a0de \u00a0un \u00a0proceso \u00a0en \u00a0Colombia, \u00a0pide \u00a0que se solicite a la Fiscal\u00eda \u00a0Especializada \u00a0Delegada \u00a0ante \u00a0los Jueces Penales del Circuito Especializados de \u00a0Medell\u00edn, \u00a0que \u00a0remita \u00a0copias \u00a0del \u00a0expediente radicado bajo el n\u00famero 21794, \u00a0adelantado \u00a0contra \u00a0el \u00a0se\u00f1or Alejandro Bernal Madrigal, el que se encuentra en \u00a0etapa de investigaci\u00f3n preliminar. \u00a0\u00a0<\/p>\n<p>Manifiesta que la prueba es pertinente, ya que \u00a0se \u00a0trata \u00a0del \u00a0cumplimiento \u00a0de una norma relacionada con el tr\u00e1mite que puede \u00a0llevar, \u00a0en \u00a0determinado \u00a0caso, \u00a0a \u00a0que \u00a0se \u00a0emita \u00a0concepto \u00a0desfavorable \u00a0a la \u00a0petici\u00f3n de extradici\u00f3n. \u00a0\u00a0<\/p>\n<p>3.7.8.\u00a0 \u00a0En \u00a0el \u00a0cap\u00edtulo \u00a0que \u00a0llama \u00a0\u201cPrueba relacionada con la aplicaci\u00f3n del art\u00edculo \u00a0565 \u00a0 del \u00a0 C\u00f3digo \u00a0 de \u00a0Procedimiento \u00a0Penal \u00a0en \u00a0relaci\u00f3n \u00a0con \u00a0los \u00a0Estados \u00a0Unidos\u201d, \u00a0arguye que como podr\u00eda pensarse que dicha \u00a0preceptiva \u00a0 no \u00a0 tiene \u00a0 aplicaci\u00f3n\u00a0 \u00a0en \u00a0las \u00a0relaciones \u00a0con \u00a0el \u00a0pa\u00eds \u00a0solicitante, \u00a0pide que se tenga como prueba \u201cla copia \u00a0de \u00a0la \u00a0resoluci\u00f3n \u00a0emitida \u00a0dentro \u00a0del \u00a0tr\u00e1mite \u00a0de \u00a0extradici\u00f3n del se\u00f1or \u00a0HENRY \u00a0 \u00a0 \u00a0 CASTELLANOS \u00a0 \u00a0 \u00a0 GARZ\u00d3N,\u00a0 \u00a0 solicitado \u00a0 por \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Norteam\u00e9rica, \u00a0mediante \u00a0Nota \u00a0Verbal \u00a0n\u00famero \u00a01139 \u00a0del \u00a028 \u00a0de \u00a0octubre \u00a0de 1999\u201d. \u00a0\u201cEn \u00a0esta resoluci\u00f3n suscrita por \u00a0el \u00a0Fiscal \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n \u00a0se \u00a0niega la detenci\u00f3n del solicitado con \u00a0fundamento \u00a0en \u00a0el \u00a0art\u00edculo 565 del C\u00f3digo de Procedimiento Penal\u201d. \u00a0\u00a0<\/p>\n<p>A su juicio la prueba es pertinente, ya que se \u00a0trata \u00a0del \u00a0cumplimiento \u00a0de \u00a0una \u00a0norma \u00a0relacionada \u00a0con el tr\u00e1mite que puede \u00a0llevar, \u00a0en \u00a0determinado \u00a0caso, \u00a0a \u00a0que \u00a0se \u00a0emita \u00a0concepto \u00a0desfavorable \u00a0a la \u00a0petici\u00f3n de extradici\u00f3n. \u00a0\u00a0<\/p>\n<p>3.8. \u00a0 \u00a0Finalmente, \u00a0 bajo \u00a0 el \u00a0 t\u00edtulo \u00a0\u201cTRADUCCI\u00d3N \u00a0 \u00a0OFICIAL \u00a0 \u00a0DE \u00a0 \u00a0LOS \u00a0 \u00a0DOCUMENTOS \u00a0APORTADOS\u201d, \u00a0sostiene que la documentaci\u00f3n allegada \u00a0al \u00a0tr\u00e1mite, \u00a0conforme \u00a0a \u00a0la simple confrontaci\u00f3n formal, tal como lo hace la \u00a0Corte, \u00a0no \u00a0cumple con el requisito estatuido en el art\u00edculo 259 del C\u00f3digo de \u00a0Procedimiento \u00a0Civil. \u00a0As\u00ed \u00a0mismo, \u00a0que \u00a0al \u00a0tenor \u00a0del art\u00edculo 260 del mismo \u00a0estatuto, \u00a0observa \u00a0la \u00a0ausencia de la traducci\u00f3n de algunos documentos, lo que \u00a0conlleva \u00a0a que se emita concepto desfavorable a la petici\u00f3n de extradici\u00f3n, o \u00a0que se le decreten las probanzas incoadas. \u00a0\u00a0<\/p>\n<p>Segundo \u00a0escrito \u00a0\u00a0<\/p>\n<p>Solicita \u00a0la \u00a0suspensi\u00f3n \u00a0del \u00a0tr\u00e1mite \u00a0de \u00a0extradici\u00f3n, \u00a0toda \u00a0vez que la sentencia de tutela N\u00b0 1736 del 12 de diciembre \u00a0de \u00a02000, dictada por la Corte Constitucional, ampar\u00f3 el derecho vulnerado a su \u00a0defendido, \u00a0 \u00a0para \u00a0 \u00a0lo \u00a0 \u00a0cual \u00a0 \u00a0se \u00a0 \u00a0permite \u00a0 \u00a0transcribir \u00a0 \u00a0sus \u00a0 partes \u00a0pertinentes. \u00a0\u00a0<\/p>\n<p>Dice \u00a0que \u00a0la citada Corporaci\u00f3n estableci\u00f3 \u00a0claramente \u00a0que \u00a0es \u00a0requisito \u00a0de \u00a0procedibilidad \u00a0de \u00a0la \u00a0extradici\u00f3n \u00a0que la \u00a0Fiscal\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0se \u00a0pronuncie previamente, \u201cen \u00a0cuanto al cumplimiento del art\u00edculo 35 de la Constituci\u00f3n y de \u00a0sus \u00a0obligaciones \u00a0constitucionales \u00a0y legales, especialmente lo relacionado con \u00a0el \u00a0art\u00edculo \u00a013 \u00a0del \u00a0C\u00f3digo \u00a0Penal que establece la territorialidad para los \u00a0efectos \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0investigaci\u00f3n \u00a0 ordenada \u00a0 a \u00a0 su \u00a0 despacho\u201d, lo que en efecto no ha sucedido. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES\u00a0 \u00a0DE\u00a0 LA\u00a0 CORTE \u00a0\u00a0<\/p>\n<p>Sobre \u00a0 las \u00a0 pruebas \u00a0solicitadas \u00a0\u00a0<\/p>\n<p>Teniendo en cuenta que el concepto de la Corte \u00a0acerca \u00a0de \u00a0la \u00a0viabilidad \u00a0o \u00a0no \u00a0de \u00a0la \u00a0extradici\u00f3n, \u00a0se \u00a0fundamenta \u00a0en \u00a0la \u00a0demostraci\u00f3n \u00a0plena \u00a0de la identidad del solicitado, en la validez formal de la \u00a0documentaci\u00f3n \u00a0presentada, \u00a0en \u00a0el \u00a0principio de la doble incriminaci\u00f3n, en la \u00a0equivalencia \u00a0de \u00a0la \u00a0providencia \u00a0proferida en el extranjero y, cuando fuere el \u00a0caso, \u00a0en \u00a0el \u00a0cumplimiento de los tratados p\u00fablicos (art. 520 de la Ley 600 de \u00a02000, \u00a0antes \u00a0art. \u00a0558 \u00a0del C. de P. P.), necesario es entonces que las pruebas \u00a0solicitadas \u00a0tengan \u00a0estricta \u00a0relaci\u00f3n \u00a0con \u00a0dichos \u00a0aspectos \u00a0y \u00a0que \u00a0as\u00ed lo \u00a0sustente el peticionario. \u00a0\u00a0<\/p>\n<p>Ahora \u00a0bien, \u00a0como \u00a0quiera \u00a0que \u00a0la \u00a0presente \u00a0solicitud \u00a0de \u00a0extradici\u00f3n no se rige por tratados internacionales, en raz\u00f3n a \u00a0que \u00a0con \u00a0el \u00a0Gobierno \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica no existe ning\u00fan \u00a0Convenio \u00a0aplicable \u00a0al caso, tal como lo conceptu\u00f3 el Ministerio de Relaciones \u00a0Exteriores, \u00a0es \u00a0procedente \u00a0obrar de conformidad con las normas pertinentes del \u00a0C\u00f3digo de Procedimiento Penal vigente. \u00a0\u00a0<\/p>\n<p>Consecuente con lo precedentemente dicho, las \u00a0pruebas \u00a0solicitadas \u00a0por \u00a0la defensa ser\u00e1n negadas en su totalidad, de acuerdo \u00a0con \u00a0las \u00a0razones \u00a0que \u00a0se \u00a0exponen a continuaci\u00f3n y conforme a los par\u00e1metros \u00a0fijados por los art\u00edculos 235 y 518 del nuevo C. de P. Penal. \u00a0\u00a0<\/p>\n<p>1. \u00a0En \u00a0cuanto \u00a0hace \u00a0relaci\u00f3n a las pruebas \u00a0relacionadas \u00a0en \u00a0el \u00a0numeral 3.7.1. de los antecedentes de esta providencia, en \u00a0el \u00a0que \u00a0solicita \u00a0que \u00a0las \u00a0autoridades \u00a0de \u00a0los Estados Unidos y el respectivo \u00a0Fiscal \u00a0que \u00a0conoce del proceso penal que cursa en dicha pa\u00eds, especifiquen, de \u00a0manera \u00a0clara \u00a0y \u00a0precisa, \u00a0tanto \u00a0los hechos como los soportes que sirvieron de \u00a0sustento \u00a0de \u00a0los \u00a0mismos, \u00a0el nombre del defensor del acusado y las actuaciones \u00a0que \u00a0ha \u00a0cumplido \u00a0y \u00a0las motivaciones que apoyaron el dolo y la responsabilidad \u00a0del \u00a0requerido \u00a0en \u00a0extradici\u00f3n, \u00a0elementos \u00a0de \u00a0juicio con los que se pretende \u00a0complementar \u00a0la \u00a0documentaci\u00f3n \u00a0allegada \u00a0y reunir los requisitos b\u00e1sicos que \u00a0exige \u00a0nuestra \u00a0resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n, \u00a0se \u00a0negar\u00e1n \u00a0por \u00a0no \u00a0cumplir los \u00a0presupuestos de conducencia y pertinencia. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, \u00a0si \u00a0bien la validez formal de la \u00a0documentaci\u00f3n \u00a0presentada \u00a0por \u00a0las autoridades del pa\u00eds solicitante es uno de \u00a0los \u00a0aspectos \u00a0que \u00a0se \u00a0debe \u00a0considerar en el respectivo concepto, sin embargo, \u00a0pese \u00a0al \u00a0gran \u00a0esfuerzo argumentativo del defensor, lo que termina cuestionando \u00a0no \u00a0es \u00a0la \u00a0deficiencia de la documentaci\u00f3n aportada, sino los actos que se han \u00a0desarrollado \u00a0al \u00a0interior \u00a0del \u00a0proceso \u00a0en el cual se solicita la extradici\u00f3n \u00a0de\u00a0 \u00a0Santiago V\u00e9lez Vel\u00e1squez, aspectos sobre los cuales la Sala no tiene \u00a0competencia, \u00a0 ya \u00a0 que \u00a0 la \u00a0 misma \u00a0 recae \u00a0 en \u00a0 los \u00a0 tribunales \u00a0del \u00a0pa\u00eds \u00a0requirente. \u00a0\u00a0<\/p>\n<p>Sobre \u00a0estos \u00a0cuestionamientos, \u00a0es necesario \u00a0recordar \u00a0que, \u00a0en pret\u00e9ritas oportunidades, con criterio reiterado, la Sala se \u00a0ha \u00a0pronunciado, \u00a0en \u00a0el \u00a0sentido \u00a0de que su labor se \u00a0centra, \u00a0exclusivamente, en emitir el respectivo concepto dentro de los precisos \u00a0par\u00e1metros \u00a0que \u00a0estatuye el art\u00edculo 520 del nuevo C. de P. Penal (antes art. \u00a0558), \u00a0sin \u00a0que \u00a0est\u00e9 contemplado pronunciarse sobre la validez o el m\u00e9rito de \u00a0los \u00a0elementos \u00a0de \u00a0juicio en que se apoya la petici\u00f3n de extradici\u00f3n ni sobre \u00a0los \u00a0cargos \u00a0que \u00a0se \u00a0imputan \u00a0en el respectivo indictment, pues, de hacerlo, se \u00a0estar\u00eda \u00a0entrometiendo en la soberan\u00eda y en la jurisdicci\u00f3n de los tribunales \u00a0del \u00a0Estado solicitante, por lo que dichos aspectos deben discutirse al interior \u00a0del respectivo proceso. \u00a0\u00a0<\/p>\n<p>Sobre el punto, se ha dicho: \u00a0<\/p>\n<p>\u201cLa \u00a0extradici\u00f3n, \u00a0ha sido sostenido por la Corte, no corresponde a la noci\u00f3n de un \u00a0proceso \u00a0judicial \u00a0en \u00a0el que se juzgue la conducta de aqu\u00e9l a quien se reclama \u00a0en \u00a0 extradici\u00f3n, \u00a0 sino \u00a0 que \u00a0 obedece \u00a0 a \u00a0un \u00a0instrumento \u00a0de \u00a0cooperaci\u00f3n \u00a0internacional \u00a0previsto normativamente (Convenci\u00f3n, Tratado, Convenio, Acuerdo, \u00a0Constituci\u00f3n \u00a0o ley, seg\u00fan el caso), con la finalidad de evitar la evasi\u00f3n de \u00a0la \u00a0acci\u00f3n \u00a0de \u00a0la \u00a0justicia \u00a0por \u00a0parte \u00a0de quien ha realizado comportamientos \u00a0delictivos \u00a0escondi\u00e9ndose en territorio sobre el cual carece de competencia las \u00a0autoridades \u00a0jurisdiccionales \u00a0que \u00a0solicitan \u00a0su \u00a0presencia, \u00a0y pueda responder \u00a0personalmente \u00a0por \u00a0los \u00a0cargos \u00a0que \u00a0le \u00a0son \u00a0imputados \u00a0y por los cuales se le \u00a0convoc\u00f3 a juicio criminal. \u00a0\u00a0<\/p>\n<p>\u201cDebido a ello, \u00a0en \u00a0su \u00a0tr\u00e1mite \u00a0no \u00a0tiene \u00a0cabida \u00a0cuestionamientos \u00a0relativos \u00a0a la validez o \u00a0m\u00e9rito \u00a0de \u00a0la \u00a0prueba \u00a0recaudada \u00a0por \u00a0las \u00a0autoridades \u00a0extranjeras \u00a0sobre la \u00a0ocurrencia \u00a0del hecho, el lugar de su realizaci\u00f3n, la forma de participaci\u00f3n o \u00a0el \u00a0grado \u00a0de \u00a0responsabilidad \u00a0del \u00a0encausado; \u00a0la \u00a0normatividad que proh\u00edbe y \u00a0sanciona \u00a0el \u00a0hecho \u00a0delictivo; \u00a0la \u00a0calificaci\u00f3n jur\u00eddica correspondiente; la \u00a0competencia \u00a0del \u00a0\u00f3rgano jurisdicente; la validez del tr\u00e1mite en el cual se le \u00a0acusa; \u00a0o \u00a0la \u00a0pena \u00a0que le corresponder\u00eda purgar para el caso de ser declarado \u00a0penalmente \u00a0responsable; pues tales aspectos corresponden a la \u00f3rbita exclusiva \u00a0y \u00a0excluyente \u00a0de \u00a0las \u00a0autoridades \u00a0del \u00a0pa\u00eds \u00a0que \u00a0eleva \u00a0la \u00a0solicitud, y su \u00a0postulaci\u00f3n \u00a0o controversia debe hacerse al interior del respectivo proceso con \u00a0recurso \u00a0a \u00a0los \u00a0instrumentos dial\u00e9cticos que prevea la legislaci\u00f3n del Estado \u00a0que \u00a0formula \u00a0el \u00a0pedido\u201d \u00a01. \u00a0\u00a0<\/p>\n<p>En \u00a0conclusi\u00f3n \u00a0las \u00a0citadas \u00a0pruebas \u00a0no se \u00a0decretar\u00e1n. \u00a0\u00a0<\/p>\n<p>2. \u00a0Las \u00a0pruebas \u00a0relacionadas \u00a0en el numeral \u00a03.7.2., \u00a0las \u00a0que \u00a0tienen por objeto \u201ccomplementar el \u00a0concepto \u00a0del \u00a0Ministerio \u00a0de Relaciones Exteriores\u201d, \u00a0para \u00a0lo \u00a0cual \u00a0solicita \u00a0que \u00a0dicho Ministerio remita una serie de instrumentos \u00a0internacionales, \u00a0con \u00a0su \u00a0respectiva \u00a0certificaci\u00f3n \u00a0de \u00a0vigencia, \u00a0el \u00a0oficio \u00a0fechado \u00a0el \u00a06 \u00a0de \u00a0diciembre \u00a0de \u00a01999, \u00a0suscrito \u00a0por el Ministro de la citada \u00a0Cartera, \u00a0el \u00a0acta de compromiso de reciprocidad por parte de los Estados Unidos \u00a0y \u00a0un \u00a0listado \u00a0de \u00a0las peticiones de extradici\u00f3n que Colombia ha elevado en la \u00a0\u00faltima d\u00e9cada, por superfluas e improcedentes no se decretar\u00e1n. \u00a0\u00a0<\/p>\n<p>Como \u00a0se \u00a0ha \u00a0sostenido, \u00a0la \u00a0Corte \u00a0no puede \u00a0inmiscuirse \u00a0en \u00a0el \u00a0tr\u00e1mite que adelanta el gobierno nacional quien, dentro de \u00a0su \u00a0autonom\u00eda \u00a0pol\u00edtica, \u00a0no \u00a0solo le da inicio, sino que le pone fin mediante \u00a0una \u00a0resoluci\u00f3n \u00a0administrativa, \u00a0careciendo, \u00a0por \u00a0ende, \u00a0de \u00a0la facultad para \u00a0se\u00f1alar \u00a0la \u00a0forma \u00a0o \u00a0el \u00a0sentido \u00a0del \u00a0concepto \u00a0del Ministerio de Relaciones \u00a0Exteriores, \u00a0pues \u00a0adem\u00e1s \u00a0de \u00a0que \u00a0con \u00a0ello \u00a0se \u00a0estar\u00eda atentando contra la \u00a0autonom\u00eda \u00a0e independencia de las Ramas del Poder P\u00fablico, se quebrantar\u00eda el \u00a0principio \u00a0 de \u00a0 legalidad, \u00a0al \u00a0arrogarse \u00a0facultades \u00a0no \u00a0establecidas \u00a0en \u00a0la \u00a0Constituci\u00f3n \u00a0y \u00a0en \u00a0la \u00a0ley. \u00a0Si \u00a0conforme al art\u00edculo 514 del C. de P. P, es \u00a0aquel \u00a0Ministerio \u00a0al \u00a0que \u00a0le \u00a0compete \u00a0la \u00a0funci\u00f3n de se\u00f1alar si es del caso \u00a0proceder \u00a0con sujeci\u00f3n a convenciones o usos internacionales o si se debe obrar \u00a0conforme \u00a0a \u00a0las \u00a0normas \u00a0del \u00a0C. \u00a0de \u00a0P. \u00a0Penal, \u00a0la Corte debe atenerse a \u00e9l, \u00a0resultando \u00a0impertinente cualquier prueba a trav\u00e9s de la cual entre a dirigir o \u00a0controlar el marco normativo aplicable al caso. \u00a0\u00a0<\/p>\n<p>De \u00a0otro \u00a0lado, reit\u00e9rese que el numeral 2\u00b0 \u00a0del \u00a0art\u00edculo \u00a0189 \u00a0de \u00a0la \u00a0Constituci\u00f3n \u00a0Pol\u00edtica \u00a0estatuye \u00a0que \u00a0a \u00a0la Rama \u00a0Ejecutiva \u00a0le \u00a0corresponde \u00a0la \u00a0Direcci\u00f3n \u00a0de \u00a0las \u00a0Relaciones Internacionales, \u00a0raz\u00f3n \u00a0por la cual, mientras la reciprocidad no sea un principio expreso dentro \u00a0del \u00a0tratado \u00a0o \u00a0la \u00a0ley \u00a0que \u00a0rija el tr\u00e1mite de extradici\u00f3n, su an\u00e1lisis le \u00a0corresponde \u00a0en \u00a0Colombia \u00a0al \u00a0Presidente \u00a0de la Rep\u00fablica como Jefe de Estado, \u00a0Jefe del Gobierno y Suprema Autoridad Administrativa. \u00a0\u00a0<\/p>\n<p>En \u00a0consecuencia, como quiera que se est\u00e1 en \u00a0la \u00a0fase \u00a0jurisdiccional \u00a0de \u00a0este \u00a0tr\u00e1mite, no siendo el momento procesal para \u00a0allegar \u00a0elementos \u00a0de \u00a0juicio \u00a0tendientes \u00a0a verificar asuntos propios de otras \u00a0competencias, \u00a0 no \u00a0 se \u00a0 decretar\u00e1n \u00a0 las \u00a0 pruebas \u00a0 solicitadas.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>3. \u00a0En \u00a0lo \u00a0que \u00a0ata\u00f1e \u00a0a \u00a0los \u00a0medios \u00a0de \u00a0convicci\u00f3n \u00a0 rese\u00f1ados \u00a0 en \u00a0 el \u00a0numeral \u00a03.7.3., \u00a0esto \u00a0es, \u00a0\u201cPRUEBAS \u00a0 RELACIONADAS \u00a0 CON \u00a0 EL \u00a0 ART\u00cdCULO \u00a0551 \u00a0DEL \u00a0C\u00d3DIGO \u00a0DE \u00a0PROCEDIMIENTO \u00a0PENAL\u201d \u00a0(hoy \u00a0art\u00edculo 513 de la Ley \u00a0600 \u00a0de \u00a02000), \u00a0en \u00a0el que solicita que las correspondientes autoridades de los \u00a0Estados \u00a0 Unidos \u00a0 de \u00a0 Am\u00e9rica \u00a0 remitan \u00a0 copias, \u00a0debidamente \u00a0traducidas \u00a0y \u00a0autenticadas, \u00a0de \u00a0una \u00a0serie de normas penales, de las leyes de extradici\u00f3n de \u00a01982, \u00a0del \u00a0Manual \u00a0de \u00a0Instrucci\u00f3n \u00a0de \u00a0los \u00a0Jurados \u00a0de \u00a0dicho pa\u00eds y que el \u00a0Ministerio \u00a0de Justicia y del Derecho certifique que la se\u00f1ora Sandra R. Acosta \u00a0es \u00a0 \u00a0traductora \u00a0 \u00a0oficial, \u00a0 \u00a0igualmente \u00a0 se \u00a0 negar\u00e1n \u00a0 por \u00a0 in\u00fatiles \u00a0 e \u00a0improcedentes.\u00a0 \u00a0\u00a0<\/p>\n<p>Al \u00a0respecto \u00a0debe decirse que los documentos \u00a0aportados \u00a0 por \u00a0 v\u00eda \u00a0diplom\u00e1tica \u00a0contienen \u00a0la \u00a0suficiente \u00a0informaci\u00f3n \u00a0e \u00a0ilustraci\u00f3n \u00a0para que la Sala pronuncie su concepto, ajustado a los par\u00e1metros \u00a0del art\u00edculo 520 del nuevo C\u00f3digo de Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, en el expediente aparecen las leyes y \u00a0las \u00a0constancias \u00a0expedidas \u00a0por las correspondientes autoridades de los Estados \u00a0Unidos \u00a0de Am\u00e9rica, en las que se certifica sobre la legalidad y autenticaci\u00f3n \u00a0de \u00a0los documentos que se allegaron a la solicitud de extradici\u00f3n, instrumentos \u00a0que, \u00a0por \u00a0lo \u00a0dem\u00e1s, \u00a0no s\u00f3lo cuentan con el aval de la C\u00f3nsul en Washington \u00a0sino \u00a0tambi\u00e9n \u00a0de \u00a0los Ministerios de Relaciones Exteriores y de Justicia y del \u00a0Derecho, \u00a0elementos \u00a0de \u00a0juicio \u00a0suficientes \u00a0para \u00a0que \u00a0la \u00a0Sala pueda entrar a \u00a0establecer \u00a0si \u00a0se \u00a0cumpli\u00f3 \u00a0o \u00a0no \u00a0con el requisito de la validez formal de la \u00a0documentaci\u00f3n presentada. \u00a0\u00a0<\/p>\n<p>4. \u00a0En \u00a0el \u00a0punto \u00a03.7.4., \u00a0solicita \u00a0que \u00a0se \u00a0alleguen \u00a0copias \u00a0de los documentos atinentes a la asistencia judicial requerida \u00a0por \u00a0 los \u00a0 Estados \u00a0 Unidos \u00a0 y \u00a0a \u00a0la \u00a0\u201cOperaci\u00f3n \u00a0Milenio\u201d \u00a0que \u00a0posee \u00a0la \u00a0Polic\u00eda \u00a0Nacional, la que \u00a0informar\u00e1 \u00a0igualmente \u00a0sobre la manera como se obtuvieron las grabaciones a que \u00a0hace \u00a0referencia \u00a0el \u00a0agente \u00a0de \u00a0la \u00a0D. \u00a0E. \u00a0A., \u00a0las \u00a0que \u00a0tambi\u00e9n \u00a0deben ser \u00a0incorporadas a este diligenciamiento. \u00a0\u00a0<\/p>\n<p>Estas pruebas, por improcedentes y superfluas, \u00a0tambi\u00e9n \u00a0se \u00a0negar\u00e1n, \u00a0ya \u00a0que \u00a0las \u00a0mismas hacen referencia al expediente que \u00a0origin\u00f3 \u00a0la \u00a0petici\u00f3n \u00a0de \u00a0extradici\u00f3n \u00a0y \u00a0no \u00a0al concepto que debe emitir la \u00a0Corte, \u00a0toda \u00a0vez \u00a0que, como qued\u00f3 visto en precedencia, el juicio de legalidad \u00a0de \u00a0las \u00a0pruebas \u00a0y su apreciaci\u00f3n son asuntos de competencia de los tribunales \u00a0for\u00e1neos y ajenos a esta tramitaci\u00f3n. \u00a0\u00a0<\/p>\n<p>5. En el numeral 3.7.5, solicita que la Corte \u00a0Suprema \u00a0 de \u00a0 los \u00a0Estados \u00a0Unidos \u00a0remita \u00a0copias, \u00a0debidamente \u00a0traducidas \u00a0y \u00a0autenticadas, \u00a0de \u00a0jurisprudencias \u00a0que \u00a0contengan un estudio jur\u00eddico sobre el \u00a0delito \u00a0 de \u00a0 conspiraci\u00f3n. \u00a0 Igualmente, \u00a0 depreca \u00a0que \u00a0las \u00a0correspondientes \u00a0autoridades \u00a0 de \u00a0 dicho \u00a0 pa\u00eds \u00a0 env\u00eden \u00a0copia \u00a0del \u00a0Manual \u00a0de \u00a0Pr\u00e1ctica \u00a0e \u00a0Instrucciones \u00a0al \u00a0Jurado \u00a0Federal\u00a0 \u00a0y \u00a0que \u00a0la \u00a0Academia de Jurisprudencia \u00a0Colombiana \u00a0certifique \u00a0si \u00a0la \u00a0conspiraci\u00f3n \u00a0es \u00a0equivalente al concierto para \u00a0delinquir. \u00a0\u00a0<\/p>\n<p>Tales \u00a0medios \u00a0de convicci\u00f3n son superfluos, \u00a0pues \u00a0siendo \u00a0cierto \u00a0que \u00a0la verificaci\u00f3n del cumplimiento del principio de la \u00a0doble \u00a0incriminaci\u00f3n \u00a0se \u00a0constituye en un aspecto integrante del concepto que, \u00a0como \u00a0culminaci\u00f3n de la fase judicial del tr\u00e1mite, debe emitir la Corte, ser\u00e1 \u00a0en \u00a0dicho \u00a0pronunciamiento donde habr\u00e1n de realizarse las precisiones atinentes \u00a0al tema, de contenido estrictamente jur\u00eddico. \u00a0\u00a0<\/p>\n<p>As\u00ed mismo, como ya se indic\u00f3 en precedencia, \u00a0el \u00a0expediente \u00a0cuenta \u00a0con \u00a0suficientes \u00a0elementos \u00a0de \u00a0juicio para que la Sala \u00a0establezca \u00a0si \u00a0los \u00a0hechos \u00a0que \u00a0motivan \u00a0la \u00a0solicitud \u00a0de extradici\u00f3n est\u00e1n \u00a0previstos \u00a0como \u00a0delitos \u00a0en \u00a0Colombia \u00a0y \u00a0reprimidos \u00a0con \u00a0pena privativa de la \u00a0libertad cuyo m\u00ednimo no sea inferior a cuatro a\u00f1os. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, en el diligenciamiento aparece la \u00a0Nota \u00a0Verbal \u00a0N\u00b0 1211 del 26 de noviembre de 1999, mediante la cual el Gobierno \u00a0de \u00a0los \u00a0Estados \u00a0Unidos de Am\u00e9rica formaliz\u00f3 la solicitud de extradici\u00f3n; el \u00a0testimonio \u00a0de \u00a0la \u00a0se\u00f1ora \u00a0Theresa \u00a0M. \u00a0B. \u00a0Van \u00a0Vliet, \u00a0una \u00a0de \u00a0las Fiscales \u00a0Especiales \u00a0que \u00a0interviene \u00a0en \u00a0el \u00a0proceso \u00a0motivo de este tr\u00e1mite; la cuarta \u00a0acusaci\u00f3n \u00a0supletoria proferida, el 18 de noviembre de 1999, dentro de la causa \u00a0N\u00b0 \u00a099-6153 CR-RYSKAMP (s)(s)(s)(s); las normas penales aplicables al caso y la \u00a0declaraci\u00f3n \u00a0que \u00a0en apoyo de la solicitud de extradici\u00f3n rindi\u00f3 el agente de \u00a0la \u00a0D.E.A. \u00a0Paul \u00a0Craine, \u00a0documentos \u00a0en \u00a0los \u00a0cuales \u00a0se \u00a0describen, \u00a0con \u00a0las \u00a0circunstancias \u00a0de tiempo, modo y lugar, las conductas imputadas al solicitado y \u00a0se concretan los delitos tipificados con ellas. \u00a0\u00a0<\/p>\n<p>Por \u00a0\u00faltimo, \u00a0sobre \u00a0el \u00a0valor \u00a0que \u00a0en este \u00a0tr\u00e1mite \u00a0tienen esa clase de documentos, la Corte ha sostenido: \u201cCon \u00a0todo, es importante precisar que de conformidad con lo previsto \u00a0por \u00a0el \u00a0art\u00edculo \u00a0551 \u00a0del \u00a0C\u00f3digo de Procedimiento Penal, el principio de la \u00a0doble \u00a0incriminaci\u00f3n, \u00a0no \u00a0se \u00a0acredita \u00a0solamente \u00a0con \u00a0el indictment, como lo \u00a0propone \u00a0 el \u00a0defensor, \u00a0pues \u00a0para \u00a0ello \u00a0reclama \u00a0la \u00a0copia \u00a0o \u00a0transcripci\u00f3n \u00a0aut\u00e9ntica \u00a0de \u00a0la \u00a0sentencia, de la resoluci\u00f3n de acusaci\u00f3n o su equivalente; \u00a0la \u00a0 indicaci\u00f3n \u00a0 exacta \u00a0 de \u00a0los \u00a0actos \u00a0que \u00a0determinaron \u00a0la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n \u00a0y \u00a0del \u00a0lugar \u00a0y \u00a0la \u00a0fecha \u00a0en \u00a0que \u00a0fueron \u00a0ejecutados, \u00a0y copia \u00a0aut\u00e9ntica \u00a0de \u00a0las \u00a0disposiciones \u00a0penales \u00a0aplicables \u00a0para el caso (numerales \u00a01,2,4). \u00a0Raz\u00f3n \u00a0por \u00a0la \u00a0cual \u00a0la \u00a0Sala tradicionalmente ha admitido para estos \u00a0efectos, \u00a0 los \u00a0 testimonios \u00a0rendidos \u00a0por \u00a0algunos \u00a0de \u00a0los \u00a0funcionarios \u00a0que \u00a0intervinieron \u00a0en la investigaci\u00f3n de los hechos de la reclamaci\u00f3n\u201d \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 2. \u00a0\u00a0<\/p>\n<p>Por \u00a0las \u00a0anteriores \u00a0razones, \u00a0las \u00a0pruebas \u00a0solicitadas se negar\u00e1n. \u00a0\u00a0<\/p>\n<p>6. \u00a0En \u00a0cuanto \u00a0hace \u00a0relaci\u00f3n a las pruebas \u00a0relacionadas \u00a0en el numeral 3.7.6., concernientes al requisito a la equivalencia \u00a0del \u00a0acto extranjero con la resoluci\u00f3n de acusaci\u00f3n, solicita que se trasladen \u00a0unas \u00a0piezas \u00a0procesales \u00a0pertenecientes \u00a0a \u00a0un \u00a0proceso \u00a0que \u00a0se adelanta en la \u00a0justicia \u00a0especializada. \u00a0As\u00ed mismo, que la Corte Suprema de los Estados Unidos \u00a0remita \u00a0copia \u00a0de unas sentencias proferidas por ese alto Tribunal. Por \u00faltimo, \u00a0que \u00a0 la \u00a0 Academia \u00a0 Colombiana \u00a0de \u00a0Jurisprudencia \u00a0emita \u00a0concepto \u00a0sobre \u00a0la \u00a0equivalencia \u00a0del indictment con la resoluci\u00f3n de acusaci\u00f3n, el que podr\u00e1 ser \u00a0apoyado \u00a0con \u00a0el \u00a0testimonio \u00a0de unos juristas nacionales que cita, elementos de \u00a0juicio que tambi\u00e9n ser\u00e1n negados por superfluos e inconducentes. \u00a0\u00a0<\/p>\n<p>Recu\u00e9rdese \u00a0 que \u00a0lo \u00a0relacionado \u00a0con \u00a0la \u00a0equivalencia \u00a0entre \u00a0el \u00a0indictment \u00a0y la resoluci\u00f3n de acusaci\u00f3n es cuesti\u00f3n \u00a0eminentemente \u00a0jur\u00eddica que la Sala debe definir al momento de rendir concepto, \u00a0por \u00a0lo \u00a0que \u00a0resulta \u00a0inoportuno \u00a0su \u00a0planteamiento \u00a0en \u00a0este momento procesal. \u00a0Adem\u00e1s, \u00a0pretender \u00a0que la Academia Colombiana de Jurisprudencia y dos abogados \u00a0indiquen \u00a0a \u00a0esta \u00a0Corporaci\u00f3n \u00a0c\u00f3mo \u00a0debe \u00a0comprender \u00a0los \u00a0alcances del tema \u00a0propuesto, \u00a0desconoce que no puede ser reemplazada en sus funciones por personas \u00a0que \u00a0carecen \u00a0de \u00a0jurisdicci\u00f3n \u00a0y competencia para intervenir en este tr\u00e1mite. \u00a0\u00a0<\/p>\n<p>Igualmente, cabe destacar que no se necesitan \u00a0medios \u00a0de \u00a0convicci\u00f3n \u00a0adicionales \u00a0a \u00a0los \u00a0incorporados \u00a0a \u00a0la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n \u00a0de \u00a0Santiago \u00a0V\u00e9lez \u00a0Vel\u00e1squez\u00a0 \u00a0para \u00a0que \u00a0la Corte, en el \u00a0concepto, \u00a0determine \u00a0si \u00a0son \u00a0o \u00a0no \u00a0equivalentes las mencionadas providencias, \u00a0pues, \u00a0como ya lo ha sostenido la Sala en casos similares a \u00e9ste, se cuenta con \u00a0la \u00a0copia \u00a0autenticada \u00a0y \u00a0traducida \u00a0de \u00a0la \u00a0cuarta acusaci\u00f3n proferida por un \u00a0Jurado \u00a0Federal \u00a0de \u00a0Fort \u00a0Lauderdale \u00a0Condado \u00a0de \u00a0Broward, \u00a0Florida, \u00a0el 18 de \u00a0noviembre \u00a0 de \u00a01999, \u00a0con \u00a0las \u00a0declaraciones \u00a0rendidas \u00a0por \u00a0los \u00a0funcionarios \u00a0judiciales \u00a0de \u00a0los \u00a0Estados Unidos, como son las de la Fiscal Federal Especial, \u00a0quien \u00a0explica \u00a0en \u00a0qu\u00e9 \u00a0consiste \u00a0y \u00a0cu\u00e1l es la naturaleza del proceso que se \u00a0adelanta \u00a0contra \u00a0el \u00a0se\u00f1or \u00a0Santiago \u00a0V\u00e9lez, \u00a0y \u00a0la del Agente Especial de la \u00a0D.E.A., \u00a0en \u00a0la \u00a0que \u00a0relacionan \u00a0pormenorizadamente \u00a0los \u00a0hechos \u00a0atribuidos al \u00a0imputado, \u00a0as\u00ed \u00a0como \u00a0de \u00a0las \u00a0normas penales aplicables al asunto, los que son \u00a0elementos \u00a0 suficientes \u00a0para \u00a0determinar \u00a0si \u00a0se \u00a0cumple \u00a0o \u00a0no \u00a0el \u00a0mencionado \u00a0requisito. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0 la \u00a0 Sala, \u00a0 en \u00a0 oportunidades \u00a0anteriores3, \u00a0ha \u00a0precisado \u00a0que \u00a0lo \u00a0que \u00a0la \u00a0ley \u00a0colombiana \u00a0exige es que la \u00a0providencia \u00a0proferida \u00a0en \u00a0el \u00a0extranjero \u00a0sea \u00a0equivalente a la resoluci\u00f3n de \u00a0acusaci\u00f3n, \u00a0no \u00a0que \u00a0contenga \u00a0los \u00a0mismos \u00a0requisitos \u00a0formales y sustanciales \u00a0exigidos \u00a0por \u00a0nuestra \u00a0legislaci\u00f3n, \u00a0pues \u00a0ello \u00a0implicar\u00eda \u00a0pretender que se \u00a0tratara \u00a0de \u00a0sistemas \u00a0judiciales id\u00e9nticos y con un mismo fundamento pol\u00edtico \u00a0criminal, lo que, sin duda, se constituir\u00eda en un absurdo. \u00a0\u00a0<\/p>\n<p>As\u00ed, \u00a0 entonces, \u00a0 los \u00a0medios \u00a0de \u00a0prueba \u00a0solicitados no se decretar\u00e1n.\u00a0 \u00a0\u00a0<\/p>\n<p>7. \u00a0En los numerales 3.7.7. y 3.7.8. solicita \u00a0que \u00a0un \u00a0juez \u00a0especializado \u00a0de Medell\u00edn remita copia del proceso que adelanta \u00a0contra \u00a0Alejando \u00a0Bernal \u00a0Madrigal y que se allegue una copia de una resoluci\u00f3n \u00a0proferida \u00a0por la Fiscal\u00eda General de la Naci\u00f3n, con el objeto de sustentar la \u00a0no \u00a0extradici\u00f3n \u00a0con base en lo preceptuado en el art\u00edculo 565 del anterior C. \u00a0de P. Penal. \u00a0\u00a0<\/p>\n<p>Al \u00a0 respecto \u00a0se \u00a0precisa \u00a0que \u00a0la \u00a0citada \u00a0preceptiva \u00a0fue \u00a0derogada \u00a0por el art\u00edculo 527 de la Ley 600 de 2000, la que, a \u00a0su \u00a0vez, \u00a0fue \u00a0declarada \u00a0inexequible \u00a0por \u00a0la \u00a0Corte \u00a0Constitucional, \u00a0mediante \u00a0sentencia del pasado 18 de julio. \u00a0\u00a0<\/p>\n<p>De \u00a0todos \u00a0modos, \u00a0dicho \u00a0tema tampoco es del \u00a0resorte \u00a0de \u00a0la \u00a0Corte, \u00a0ya \u00a0que no es uno de los aspectos sobre los cuales debe \u00a0emitir concepto, raz\u00f3n por la cual, las pruebas no se decretar\u00e1n. \u00a0\u00a0<\/p>\n<p>8. \u00a0Finalmente, \u00a0en \u00a0el \u00a0numeral 1.9., el que \u00a0titul\u00f3 \u00a0 \u201cTRADUCCI\u00d3N \u00a0OFICIAL \u00a0DE \u00a0LOS \u00a0DOCUMENTOS \u00a0APORTADOS\u201d, \u00a0 solicita \u00a0 la \u00a0 traducci\u00f3n \u00a0de \u00a0unos \u00a0documentos, \u00a0los que, en su criterio, no fueron sometidos a ese ineludible paso, \u00a0pero sin indicar a cu\u00e1les se refiere. \u00a0\u00a0<\/p>\n<p>Por \u00a0sustracci\u00f3n de materia, la prueba no se \u00a0decretar\u00e1, \u00a0 toda \u00a0 vez \u00a0 que \u00a0 se \u00a0 desconoce \u00a0cu\u00e1les \u00a0documentos \u00a0no \u00a0fueron \u00a0traducidos. \u00a0\u00a0<\/p>\n<p>9. \u00a0 Prueba \u00a0 de \u00a0oficio \u00a0\u00a0<\/p>\n<p>Como \u00a0la \u00a0Corte \u00a0observa \u00a0que \u00a0los documentos \u00a0visibles \u00a0a \u00a0los \u00a0folios \u00a02, \u00a03 \u00a0y \u00a04 \u00a0del \u00a0cuaderno \u00a0anexo \u00a0a \u00a0la \u00a0solicitud de \u00a0extradici\u00f3n, \u00a0no \u00a0han \u00a0sido \u00a0traducidos \u00a0al \u00a0castellano, \u00a0de conformidad con lo \u00a0previsto \u00a0por \u00a0el \u00a0art\u00edculo 518 de la Ley 600 de 2000 (antes art. 556 del C. de \u00a0P. \u00a0Penal), \u00a0de \u00a0oficio se ordenar\u00e1 que, dentro del t\u00e9rmino probatorio de diez \u00a0d\u00edas \u00a0m\u00e1s \u00a0el \u00a0de \u00a0la \u00a0distancia, \u00a0as\u00ed se proceda por parte del Ministerio de \u00a0Relaciones \u00a0 Exteriores, \u00a0 a \u00a0 donde \u00a0 se \u00a0remitir\u00e1n \u00a0copias \u00a0legibles \u00a0de \u00a0los \u00a0mismos. \u00a0\u00a0<\/p>\n<p>10. \u00a0 Acotaci\u00f3n \u00a0final \u00a0\u00a0<\/p>\n<p>En lo que ata\u00f1e a las inquietudes que plantea \u00a0el \u00a0memorialista \u00a0al \u00a0inicio \u00a0de \u00a0su \u00a0escrito, \u00a0la Sala las resuelve como sigue: \u00a0\u00a0<\/p>\n<p>10.1. \u00a0La \u00a0afirmaci\u00f3n, \u00a0seg\u00fan la cual, a su \u00a0defendido \u00a0no \u00a0se \u00a0le notific\u00f3 el auto por medio del cual se abri\u00f3 el t\u00e9rmino \u00a0probatorio \u00a0de este tr\u00e1mite, no es cierta, toda vez que en el expediente consta \u00a0que \u00a0la providencia fechada el 15 de enero de 2000, fue personalmente notificada \u00a0a \u00a0Santiago V\u00e9lez Vel\u00e1squez, seg\u00fan constancia visible al folio 73 de cuaderno \u00a0de \u00a0la \u00a0Corte. As\u00ed mismo, el auto dictado el 19 de julio siguiente, mediante el \u00a0cual \u00a0 se \u00a0orden\u00f3 \u00a0correr \u00a0el \u00a0citado \u00a0traslado, \u00a0tambi\u00e9n \u00a0le \u00a0fue \u00a0notificado \u00a0personalmente, \u00a0tal \u00a0como \u00a0aparece \u00a0en \u00a0el \u00a0acta \u00a0visible \u00a0al \u00a0folio \u00a0195 \u00a0de la \u00a0actuaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Por consiguiente, ninguna \u00a0irregularidad se present\u00f3 al respecto. \u00a0\u00a0<\/p>\n<p>10.2. \u00a0En \u00a0cuanto \u00a0a \u00a0las \u00a0dem\u00e1s \u00a0peticiones, \u00a0esto \u00a0es, \u00a0que \u00a0el \u00a0indictment \u00a0no \u00a0es \u00a0equivalente \u00a0con la \u00a0resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n, \u00a0que \u00a0la \u00a0documentaci\u00f3n \u00a0no \u00a0re\u00fane los requisitos \u00a0legales, \u00a0 que \u00a0el \u00a0expediente \u00a0debe \u00a0devolverse \u00a0al \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores \u00a0para \u00a0que \u00a0rinda \u00a0el \u00a0concepto en debida forma y que el principio de \u00a0reciprocidad \u00a0no \u00a0se \u00a0ha \u00a0tenido \u00a0en \u00a0cuenta, \u00a0son \u00a0inquietudes \u00a0que ya han sido \u00a0resueltas \u00a0en \u00a0el cuerpo de esta decisi\u00f3n, razones por las cuales las mismas no \u00a0tienen vocaci\u00f3n de \u00e9xito.\u00a0 \u00a0\u00a0<\/p>\n<p>Segundo \u00a0escrito \u00a0\u00a0<\/p>\n<p>El \u00a0defensor \u00a0de \u00a0Santiago \u00a0V\u00e9lez Vel\u00e1squez \u00a0solicita \u00a0la suspensi\u00f3n del proceso, apoyado en el fallo de tutela N\u00b0 1736 del \u00a012 \u00a0de \u00a0diciembre \u00a0de \u00a02000, \u00a0pues, \u00a0a \u00a0su \u00a0juicio, \u00a0estima \u00a0como \u00a0requisito \u00a0de \u00a0procedibilidad \u00a0de \u00a0este \u00a0tr\u00e1mite, \u00a0que \u00a0la \u00a0Fiscal\u00eda General de la Naci\u00f3n se \u00a0pronuncie \u00a0si \u00a0los \u00a0hechos \u00a0por \u00a0los \u00a0cuales \u00a0es \u00a0requerido su procurado, fueron \u00a0realizados o no en Colombia. \u00a0\u00a0<\/p>\n<p>En cuanto a este tema, de manera reiterada la \u00a0Sala ha sostenido: \u00a0\u00a0<\/p>\n<p>\u201cLo anterior, no \u00a0significa, \u00a0como \u00a0parece \u00a0entenderlo \u00a0el \u00a0memorialista, que la actuaci\u00f3n que le \u00a0corresponde \u00a0adelantar \u00a0a \u00a0la \u00a0Corte en esta clase de asuntos quede supeditada a \u00a0que \u00a0previamente \u00a0se \u00a0determine \u00a0si \u00a0los hechos que dan origen a la solicitud de \u00a0extradici\u00f3n \u00a0ocurrieron \u00a0o \u00a0no en territorio colombiano, pues, como se se\u00f1al\u00f3 \u00a0en \u00a0precedencia, \u00a0ese \u00a0no \u00a0es \u00a0tema del que le corresponda ocuparse a efectos de \u00a0emitir \u00a0el \u00a0concepto \u00a0que \u00a0seg\u00fan \u00a0el art\u00edculo 558 del C\u00f3digo de Procedimiento \u00a0Penal \u00a0se \u00a0exige de esta Corporaci\u00f3n; m\u00e1s a\u00fan cuando la intervenci\u00f3n de esta \u00a0Corte \u00a0no \u00a0es \u00a0de car\u00e1cter judicial y mucho menos decisoria, toda vez que es el \u00a0Ejecutivo \u00a0el \u00a0que \u00a0definitivamente resuelve si accede o no al requerimiento del \u00a0pa\u00eds \u00a0extranjero \u00a0\u2013en caso \u00a0de \u00a0que \u00a0el \u00a0concepto sea favorable- y, por ende, es all\u00ed donde adquieren plena \u00a0validez \u00a0e \u00a0injerencia los resultados y determinaciones que al respecto emita el \u00a0ente investigador. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0tanto, \u00a0tampoco \u00a0se \u00a0acceder\u00e1 \u00a0a lo \u00a0solicitado. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo expuesto, la CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0SALA \u00a0DE \u00a0CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>R E S U E L V E \u00a0<\/p>\n<p>1. NEGAR \u00a0la \u00a0pr\u00e1ctica de las pruebas pedidas por el defensor del ciudadano \u00a0SANTIAGO \u00a0V\u00c9LEZ \u00a0VEL\u00c1SQUEZ, \u00a0solicitado en extradici\u00f3n. \u00a0\u00a0<\/p>\n<p>2. \u00a0 DE \u00a0 OFICIO \u00a0se \u00a0DISPONE, \u00a0dentro \u00a0del per\u00edodo probatorio, el cual \u00a0corre \u00a0por \u00a0el \u00a0t\u00e9rmino \u00a0de \u00a0diez \u00a0d\u00edas, m\u00e1s el de la distancia (art. 518 del \u00a0nuevo \u00a0C. \u00a0de P.P.), oficiar al Ministerio de Relaciones Exteriores a fin de que \u00a0se \u00a0efect\u00fae \u00a0la \u00a0traducci\u00f3n oficial al castellano de los documentos visibles a \u00a0los \u00a0 folios \u00a0 2, \u00a0 3 \u00a0 y \u00a0 4 \u00a0 del \u00a0 cuaderno \u00a0 anexo \u00a0 a \u00a0 la \u00a0 solicitud \u00a0 de \u00a0extradici\u00f3n. \u00a0\u00a0<\/p>\n<p>Para \u00a0tal efecto, por Secretar\u00eda de la Sala, \u00a0rem\u00edtasele copia de las piezas procesales indicadas. \u00a0\u00a0<\/p>\n<p>3. \u00a0 \u00a0 NO \u00a0ACCEDER \u00a0a \u00a0las \u00a0peticiones \u00a0elevadas \u00a0por \u00a0el \u00a0citado \u00a0defensor. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, notif\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>CARLOS \u00a0EDUARDO \u00a0MEJ\u00cdA \u00a0ESCOBAR \u00a0\u00a0<\/p>\n<p>FERNANDO \u00a0E. \u00a0ARBOLEDA \u00a0RIPOLL \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0JORGE E. C\u00d3RDOBA POVEDA \u00a0\u00a0<\/p>\n<p>HERMAN \u00a0 GAL\u00c1N \u00a0 CASTELLANOS \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0CARLOS \u00a0 AUGUSTO \u00a0 GALVEZ \u00a0 ARGOTE \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>JORGE \u00a0ANIBAL \u00a0G\u00d3MEZ \u00a0GALLEGO \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0EDGAR \u00a0 \u00a0LOMBANA \u00a0TRUJILLO \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>ALVARO \u00a0ORLANDO \u00a0P\u00c9REZ PINZ\u00d3N \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0NILSON PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>TERESA RU\u00cdZ NU\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p>1 \u00a0Concepto \u00a0del \u00a08 de agosto de 2000, M.P. Dr. Fernando \u00a0Arboleda Ripoll. \u00a0\u00a0<\/p>\n<p>2 \u00a0Extradici\u00f3n \u00a0N\u00b0 \u00a016726 \u00a0del \u00a013 \u00a0de \u00a0junio \u00a0de \u00a02000, \u00a0M.P. \u00a0Dr. Edgar Lombana \u00a0Trujillo. \u00a0\u00a0<\/p>\n<p>3 Ver, \u00a0entre \u00a0otras, \u00a0extradici\u00f3n \u00a016724 \u00a0del \u00a023 \u00a0de \u00a0agosto de 2000, M.P. Dr. Carlos \u00a0G\u00e1lvez Argote. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso N\u00b0 16703 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente: \u00a0 Dr. \u00a0JORGE \u00a0E. \u00a0C\u00d3RDOBA \u00a0POVEDA \u00a0\u00a0 Aprobado acta N\u00b0 133 \u00a0 Bogot\u00e1, D. C., cinco (5) de septiembre de dos \u00a0mil uno (2001). \u00a0\u00a0 V \u00a0 \u00a0I \u00a0 S \u00a0 TO \u00a0 S \u00a0\u00a0 Resuelve \u00a0la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4491","post","type-post","status-publish","format-standard","hentry","category-9"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/4491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=4491"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/4491\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=4491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=4491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=4491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}