{"id":4424,"date":"2023-09-08T15:14:32","date_gmt":"2023-09-08T15:14:32","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1633201-11-01\/"},"modified":"2023-09-08T15:14:32","modified_gmt":"2023-09-08T15:14:32","slug":"1633201-11-01","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/1633201-11-01\/","title":{"rendered":"16332(01-11-01)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 16332 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0Magistrado \u00a0Ponente \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Dr. JORGE ANIBAL GOMEZ GALLEGO \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Aprobado Acta No 169 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Bogot\u00e1 D. C., primero de noviembre de dos mil uno. \u00a0\u00a0<\/p>\n<p>V I S T O S \u00a0<\/p>\n<p>Mediante \u00a0sentencia \u00a0de \u00a0mayo \u00a07 \u00a0de \u00a01999 el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0C\u00facuta confirm\u00f3 la condena que en primera instancia se \u00a0hab\u00eda \u00a0impuesto al procesado\u00a0 JOSE GREGORIO RAMIREZ MENDOZA de veinticinco \u00a0(25) \u00a0a\u00f1os \u00a0de \u00a0prisi\u00f3n, \u00a0como \u00a0autor \u00a0penalmente \u00a0responsable \u00a0del \u00a0delito de \u00a0homicidio en Flower Arcila Mendoza. \u00a0\u00a0<\/p>\n<p>Como \u00a0contra \u00a0el \u00a0fallo \u00a0del \u00a0ad \u00a0quem el defensor propuso la casaci\u00f3n, \u00a0la \u00a0Corte \u00a0examinar\u00e1 \u00a0las formas b\u00e1sicas de la demanda, de conformidad con los \u00a0art\u00edculos 207 y 212 del\u00a0 C\u00f3digo de Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>HECHOS Y ACTUACION PROCESAL \u00a0<\/p>\n<p>Cuando \u00a0en \u00a0la \u00a0madrugada del 16 de julio de \u00a01995 \u00a0Flower \u00a0Arcila \u00a0se \u00a0dirig\u00eda hacia su residencia ubicada en el Barrio Alto \u00a0Pamplonita \u00a0de \u00a0la ciudad de C\u00facuta, fue abordado por un extra\u00f1o que fingiendo \u00a0ser \u00a0conocido \u00a0suyo se le acerc\u00f3 con el fementido prop\u00f3sito de entablar alg\u00fan \u00a0di\u00e1logo, \u00a0pero \u00a0como \u00a0el transe\u00fante sospechara de esta actitud, sin dar tiempo \u00a0para \u00a0reacci\u00f3n \u00a0alguna \u00a0el intruso lo lesion\u00f3 con un pu\u00f1al, produci\u00e9ndole la \u00a0muerte \u00a0cuatro \u00a0d\u00edas \u00a0despu\u00e9s \u00a0en \u00a0el Hospital Erasmo Meoz a donde hab\u00eda sido \u00a0conducido en busca de atenci\u00f3n m\u00e9dica. \u00a0\u00a0<\/p>\n<p>El \u00a0autor \u00a0del \u00a0lesionamiento, \u00a0a \u00a0quien \u00a0se \u00a0identific\u00f3 \u00a0como \u00a0JOSE \u00a0GREGORIO \u00a0RAMIREZ \u00a0MENDOZA, \u00a0fue \u00a0vinculado \u00a0al proceso \u00a0mediante \u00a0declaratoria \u00a0de \u00a0persona \u00a0ausente \u00a0y \u00a0posteriormente \u00a0acusado \u00a0por la \u00a0Fiscal\u00eda \u00a01\u00aa Seccional de C\u00facuta por el delito de homicidio simple, a trav\u00e9s \u00a0de \u00a0 resoluci\u00f3n \u00a0 que \u00a0 adquiri\u00f3 \u00a0ejecutoria \u00a0el\u00a0 \u00a023 \u00a0de \u00a0septiembre \u00a0de \u00a01996. \u00a0\u00a0<\/p>\n<p>A la etapa de juzgamiento, durante la cual se \u00a0produjo \u00a0la captura del procesado, el Juzgado 5\u00b0 Penal del Circuito de la misma \u00a0ciudad \u00a0puso fin con el fallo de enero 19 de 1999,\u00a0 por cuyo medio, adem\u00e1s \u00a0de \u00a0la \u00a0pena \u00a0principal \u00a0ya se\u00f1alada le impuso la accesoria de interdicci\u00f3n de \u00a0derechos \u00a0y \u00a0funciones p\u00fablicas por el t\u00e9rmino de diez (10) a\u00f1os y la condena \u00a0al \u00a0 pago \u00a0de \u00a0los \u00a0perjuicios \u00a0ocasionados \u00a0con \u00a0el \u00a0delito, \u00a0estimados \u00a0en \u00a0el \u00a0equivalente \u00a0a \u00a03.000 \u00a0gramos \u00a0oro \u00a0los \u00a0de \u00a0orden \u00a0material \u00a0y \u00a0a 500\u00a0 los \u00a0morales. \u00a0\u00a0<\/p>\n<p>La \u00a0sentencia de primer grado fue confirmada \u00a0integralmente \u00a0por el Tribunal Superior de C\u00facuta al desatar la impugnaci\u00f3n de \u00a0la \u00a0defensa, \u00a0y \u00a0contra \u00a0esta \u00a0decisi\u00f3n \u00a0se \u00a0interpuso \u00a0en tiempo la demanda de \u00a0casaci\u00f3n que ahora ocupa la atenci\u00f3n de la Sala. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>Con \u00a0sustento \u00a0en \u00a0el segundo apartado de la \u00a0causal \u00a0primera \u00a0de casaci\u00f3n prevista en el art\u00edculo 207 del estatuto procesal \u00a0penal, \u00a0un \u00a0solo \u00a0cargo \u00a0formula \u00a0el \u00a0denunciante contra la sentencia de segundo \u00a0grado. \u00a0\u00a0<\/p>\n<p>Afirma \u00a0el \u00a0demandante \u00a0que \u00e9sta vulnera de \u00a0manera \u00a0indirecta \u00a0el \u00a0art\u00edculo \u00a0294 \u00a0del estatuto procesal penal\u00a0 vigente \u00a0para \u00a0la \u00a0\u00e9poca \u00a0(igual \u00a0al \u00a0277 \u00a0de la ley 600 de 2000) debido al error en que \u00a0incurri\u00f3 \u00a0el\u00a0 ad quem al \u00a0\u201capreciar\u201d \u00a0 \u00a0 los \u00a0testimonios \u00a0 de \u00a0Reinaldo \u00a0Manrique \u00a0Torres, \u00a0Henry \u00a0Antonio \u00a0Fuentes \u00a0y \u00a0Henry \u00a0Quiroz,\u00a0 \u00a0 error \u00a0 que \u00a0 se \u00a0 configura, \u00a0 seg\u00fan \u00a0 sus \u00a0propias \u00a0palabras, \u00a0\u201cal \u00a0 hacer \u00a0 una \u00a0 evaluaci\u00f3n \u00a0 de \u00a0 los \u00a0 mismos \u00a0distorsionando el mismo contenido probatorio que ellos tienen\u201d. \u00a0\u00a0<\/p>\n<p>Explica luego el censor que la incorrecci\u00f3n \u00a0consisti\u00f3 \u00a0 en \u00a0 que \u00a0 el \u00a0 Tribunal \u00a0al \u00a0igual \u00a0que \u00a0el \u00a0juzgado \u00a0le \u00a0restaron \u00a0\u201ccredibilidad\u201d \u00a0a dichos \u00a0testimonios, \u00a0los \u00a0cuales \u00a0demostraban \u00a0la \u00a0causal \u00a0de justificaci\u00f3n (leg\u00edtima \u00a0defensa) \u00a0dentro de la cual actu\u00f3 su patrocinado, la que adem\u00e1s fue descartada \u00a0desde \u00a0un \u00a0comienzo con el bifronte argumento de que el procesado no compareci\u00f3 \u00a0ante \u00a0las \u00a0autoridades reci\u00e9n ocurridos los hechos y luego en la indagatoria se \u00a0present\u00f3 como v\u00edctima. \u00a0\u00a0<\/p>\n<p>Reitera que no obstante provenir dos de esos \u00a0testimonios \u00a0de \u00a0servidores \u00a0p\u00fablicos, \u00a0fueron \u00a0desestimados \u00a0en tanto s\u00f3lo se \u00a0tuvieron \u00a0en cuenta aspectos que carec\u00edan de relevancia para\u00a0 \u201cprobar \u00a0 lo \u00a0 sustancial\u201d \u00a0 de \u00a0esta \u00a0investigaci\u00f3n, \u00a0lo \u00a0cual, \u00a0en su sentir, entra\u00f1a una particular forma de error \u00a0de hecho. \u00a0\u00a0<\/p>\n<p>Al \u00a0referirse \u00a0al \u00a0testimonio \u00a0del \u00a0agente \u00a0Manrique \u00a0Torres,\u00a0 \u00a0acota \u00a0el \u00a0demandante \u00a0que \u00a0el Tribunal le \u201cquita \u00a0 \u00a0el \u00a0 \u00a0valor \u00a0 \u00a0probatorio \u00a0 que \u00a0 tiene, \u00a0 apreci\u00e1ndolo \u00a0err\u00f3neamente\u201d, \u00a0 rest\u00e1ndole \u00a0credibilidad \u00a0por \u00a0su \u00a0contradicci\u00f3n \u00a0con \u00a0lo \u00a0demostrado \u00a0en \u00a0el \u00a0proceso, \u00a0cuando lo cierto es que a \u00a0partir \u00a0de \u00a0su \u00a0dicho \u00a0quedaba \u00a0claro \u00a0que \u00a0la \u00a0acci\u00f3n de su patrocinado estaba \u00a0amparada por la ya referida causal justificativa. \u00a0\u00a0<\/p>\n<p>Similar \u00a0cr\u00edtica \u00a0hace a la ponderaci\u00f3n de \u00a0otro \u00a0testimonio,\u00a0 el de Jos\u00e9 Carmelo S\u00e1nchez, se\u00f1alando que lo afirmado \u00a0por \u00a0este \u00a0ciudadano \u00a0\u201ces \u00a0totalmente diferente a la \u00a0apreciaci\u00f3n \u00a0que \u00a0tienen \u00a0del mismo los juzgadores de instancia\u201d, \u00a0porque \u00a0a \u00a0quien se\u00f1ala como persecutor de la v\u00edctima es persona \u00a0distinta \u00a0a \u00a0su \u00a0patrocinado. \u00a0Y \u00a0luego \u00a0de \u00a0transcribir \u00a0un \u00a0aparte \u00a0del \u00a0fallo \u00a0demandado, \u00a0anota que el simple cotejo de aqu\u00e9l testimonio con lo asegurado por \u00a0los \u00a0jueces \u00a0de \u00a0primera \u00a0y \u00a0segunda instancia, autoriza concluir que\u00a0 a la \u00a0misma \u00a0le \u00a0agregaron \u00a0\u201cun \u00a0valor \u00a0probatorio \u00a0que no \u00a0tiene\u201d, \u00a0o \u00a0mejor, \u00a0que \u00a0en \u00a0relaci\u00f3n con el mismo, \u00a0\u201csostienen afirmaciones y expresiones que este nunca \u00a0dijo\u201d. \u00a0\u00a0<\/p>\n<p>As\u00ed, \u00a0al \u00a0considerar demostrado el error de \u00a0hecho \u00a0 en \u00a0 que \u00a0 incurri\u00f3 \u00a0 especialmente \u00a0 el \u00a0 ad \u00a0quem,\u00a0 solicita la casaci\u00f3n de la sentencia para \u00a0que \u00a0en \u00a0esta \u00a0sede \u00a0se \u00a0absuelva \u00a0al \u00a0procesado del cargo objeto de acusaci\u00f3n. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>Prima \u00a0 facie, \u00a0encuentra \u00a0la \u00a0Sala\u00a0 que la demanda formulada por el defensor del procesado \u00a0JOSE \u00a0GREGORIO \u00a0RAMIREZ MENDOZA carece de las formalidades m\u00ednimas que al tenor \u00a0de \u00a0lo \u00a0previsto por el art\u00edculo 212 del estatuto procesal penal permitan abrir \u00a0el \u00a0debate para ver de establecer si por parte del Tribunal, a cuyo cargo estuvo \u00a0la \u00a0confirmaci\u00f3n \u00a0de \u00a0la \u00a0condena, \u00a0se \u00a0incurri\u00f3 \u00a0en \u00a0los yerros cuya enmienda \u00a0pretende el casacionista pidiendo la absoluci\u00f3n de su poderdante. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, si bien el libelo cumple con las \u00a0exigencias \u00a0referidas \u00a0a \u00a0la \u00a0identificaci\u00f3n \u00a0de los sujetos procesales y de la \u00a0sentencia \u00a0impugnada, \u00a0y \u00a0contiene una somera s\u00edntesis de los hechos materia de \u00a0juzgamiento \u00a0y \u00a0de \u00a0la actuaci\u00f3n procesal, igual no acontece con la obligaci\u00f3n \u00a0de \u00a0se\u00f1alar en forma clara y precisa los fundamentos en que se apoya la causal, \u00a0lo \u00a0cual \u00a0comprende \u00a0el \u00a0se\u00f1alamiento de las normas que el recurrente considera \u00a0infringidas, \u00a0 \u00a0dejando \u00a0 la \u00a0 postulaci\u00f3n \u00a0 ayuna \u00a0 de \u00a0 identidad \u00a0 jur\u00eddica \u00a0propia. \u00a0\u00a0<\/p>\n<p>Como \u00a0la \u00a0\u00fanica \u00a0referencia \u00a0a \u00a0la \u00a0norma \u00a0supuestamente \u00a0vulnerada \u00a0se \u00a0refiere \u00a0al \u00a0art\u00edculo \u00a0294 del extinto C\u00f3digo de \u00a0Procedimiento \u00a0Penal \u00a0(igual \u00a0al \u00a0277 \u00a0del \u00a0estatuto \u00a0actual, \u00a0que \u00a0alude \u00a0a los \u00a0criterios \u00a0para \u00a0la apreciaci\u00f3n del testimonio), bien est\u00e1 se\u00f1alar de una vez \u00a0que \u00a0con esta cita no se satisface aquella exigencia formal, en la medida en que \u00a0a \u00a0una \u00a0norma \u00a0medio, de contenido exclusivamente procesal o instrumental, se le \u00a0otorga \u00a0la \u00a0connotaci\u00f3n \u00a0de \u00a0sustancial \u00a0que \u00a0no \u00a0tiene, dejando de se\u00f1alar el \u00a0precepto \u00a0 de \u00a0 aquella \u00a0naturaleza \u00a0que \u00a0por \u00a0el \u00a0yerro \u00a0aducido \u00a0hubiera \u00a0sido \u00a0mediatamente \u00a0quebrantado, \u00a0bien \u00a0por \u00a0falta \u00a0de \u00a0aplicaci\u00f3n, \u00a0ora por indebida \u00a0aplicaci\u00f3n, e incluso por err\u00f3nea interpretaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Si \u00a0a \u00a0lo anterior se suma que la censura se \u00a0presenta \u00a0con \u00a0un \u00a0planteamiento asaz equ\u00edvoco, es claro que el libelo no tiene \u00a0vocaci\u00f3n para propiciar el inicio del tr\u00e1mite casacional. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, \u00a0mientras la demanda despunta el \u00a0cargo \u00a0 afirmando \u00a0 que \u00a0 algunos \u00a0 testimonios \u00a0se \u00a0apreciaron \u00a0\u201cdistorsionando\u201d \u00a0el contenido probatorio \u00a0que \u00a0ellos \u00a0tienen, \u00a0con \u00a0lo que podr\u00eda pensarse en un error de hecho por falso \u00a0juicio \u00a0de \u00a0identidad, \u00a0seguidamente \u00a0salta \u00a0a \u00a0un reproche por error de derecho \u00a0debido \u00a0a \u00a0un \u00a0imposible \u00a0falso \u00a0juicio \u00a0de convicci\u00f3n, pues eso y no otra cosa \u00a0significa \u00a0la \u00a0afirmaci\u00f3n \u00a0de \u00a0que \u00a0al testimonio del agente Manrique Torres el \u00a0Tribunal \u00a0 le \u00a0 \u201cquita \u00a0 el \u00a0valor \u00a0probatorio \u00a0que \u00a0tiene\u201d; \u00a0obviamente que sin precisar el censor cu\u00e1l \u00a0es \u00a0 el \u00a0 valor \u00a0 establecido \u00a0 a \u00a0priori \u00a0para \u00a0dicho \u00a0medio \u00a0de \u00a0prueba \u00a0que \u00a0supuestamente \u00a0desconoci\u00f3 el \u00a0sentenciador \u00a0de segunda instancia; tarea de dif\u00edcil cumplimiento en un sistema \u00a0como \u00a0el \u00a0nuestro donde no hay tarifa probatoria y la apreciaci\u00f3n de los medios \u00a0de \u00a0convicci\u00f3n \u00a0es \u00a0libre para el juez con la \u00fanica limitaci\u00f3n de que se haga \u00a0racionalmente. \u00a0\u00a0<\/p>\n<p>Ahora \u00a0bien, \u00a0no \u00a0obstante \u00a0el \u00a0manifiesto \u00a0reproche \u00a0del \u00a0censor \u00a0de \u00a0que tanto el tribunal como el juzgado \u201cle \u00a0 \u00a0 \u00a0 \u00a0restaron \u00a0 \u00a0 \u00a0 credibilidad\u201d \u00a0a algunos testimonios, si \u00a0deponiendo \u00a0 la \u00a0exigencia \u00a0de \u00a0claridad \u00a0y \u00a0precisi\u00f3n \u00a0en \u00a0la \u00a0formulaci\u00f3n \u00a0y \u00a0fundamentaci\u00f3n \u00a0del cargo que es de rigor en la casaci\u00f3n, se llegara a aceptar \u00a0que \u00a0con \u00a0la \u00a0censura \u00a0lo \u00a0que aqu\u00e9l pretend\u00eda establecer era que el examen de \u00a0tales \u00a0declaraciones \u00a0se \u00a0hizo \u00a0a espaldas de los postulados de la sana cr\u00edtica \u00a0(error \u00a0 de \u00a0hecho \u00a0por \u00a0falso \u00a0raciocinio), \u00a0aparte \u00a0de \u00a0echarse \u00a0de \u00a0menos \u00a0el \u00a0se\u00f1alamiento \u00a0del \u00a0argumento \u00a0irracional del sentenciador en la ponderaci\u00f3n de \u00a0dichos \u00a0asertos, \u00a0o el atropello a las pautas de la ciencia o a las reglas de la \u00a0experiencia, \u00a0el dislate se traslada al terreno de la dilog\u00eda pues no se aviene \u00a0con \u00a0la \u00a0l\u00f3gica \u00a0predicar \u00a0respecto de un mismo medio de prueba su distorsi\u00f3n, \u00a0esto \u00a0es \u00a0el trastocamiento de su contenido f\u00e1ctico, y su apreciaci\u00f3n desasida \u00a0de \u00a0los par\u00e1metros de\u00a0 la sana cr\u00edtica, porque este \u00faltimo ejercicio del \u00a0intelecto, \u00a0para \u00a0que \u00a0constituya \u00a0un \u00a0desatino \u00a0de \u00a0hecho por falso raciocinio, \u00a0presupone \u00a0que la prueba se haya contemplado en su integridad material, esto es, \u00a0sin distorsiones en su contenido f\u00e1ctico. \u00a0\u00a0<\/p>\n<p>En \u00a0fin, \u00a0la \u00a0censura \u00a0a la apreciaci\u00f3n del \u00a0testimonio \u00a0del \u00a0agente \u00a0Manrique \u00a0Torres queda reducida a la no bien disimulada \u00a0inconformidad \u00a0del \u00a0censor por la cr\u00edtica que de sus atestaciones razonadamente \u00a0hizo \u00a0el \u00a0sentenciador \u00a0a \u00a0la \u00a0luz \u00a0de \u00a0otras \u00a0probanzas que dejaban sin piso la \u00a0pretendida \u00a0causal de ausencia de responsabilidad. Esto y no otra cosa es lo que \u00a0se \u00a0deduce del planteamiento de la demanda seg\u00fan el cual el tribunal desestim\u00f3 \u00a0el \u00a0 testimonio \u00a0 del \u00a0 acotado \u00a0policial \u00a0para \u00a0quitarle \u00a0credibilidad \u00a0por \u00a0su \u00a0contradicci\u00f3n \u00a0con otras probanzas del proceso, cuando a juicio del libelista a \u00a0partir \u00a0 de \u00a0aquellos \u00a0asertos \u00a0la \u00a0conducta \u00a0del \u00a0acusado \u00a0estaba \u00a0justificada. \u00a0\u00a0<\/p>\n<p>Es evidente que un planteamiento de este jaez \u00a0resulta \u00a0extra\u00f1o \u00a0a \u00a0la \u00a0casaci\u00f3n, donde el examen que el fallador hace de las \u00a0pruebas \u00a0s\u00f3lo \u00a0es \u00a0atacable \u00a0en \u00a0la medida en que est\u00e9 afectado por errores de \u00a0hecho o de derecho realmente trascendentes. \u00a0\u00a0<\/p>\n<p>En similares falencias incurre el demandante \u00a0cuando \u00a0reprocha \u00a0la \u00a0apreciaci\u00f3n que en la sentencia se hizo del testimonio de \u00a0Jos\u00e9 \u00a0Carmelo S\u00e1nchez, pues bajo el gen\u00e9rico enunciado de que sus expresiones \u00a0fueron \u00a0distorsionadas \u00a0al \u00a0ponerlo \u00a0a \u00a0decir \u00a0lo \u00a0que nunca dijo, la censura se \u00a0diluye \u00a0en \u00a0una \u00a0cr\u00edtica \u00a0abierta \u00a0al \u00a0valor \u00a0otorgado en las instancias a este \u00a0declarante, \u00a0ech\u00e1ndose \u00a0de \u00a0menos \u00a0en \u00a0procura de la demostraci\u00f3n del cargo el \u00a0se\u00f1alamiento \u00a0de \u00a0los \u00a0fragmentos \u00a0del \u00a0fallo \u00a0donde \u00a0se traiciona el contenido \u00a0f\u00e1ctico \u00a0 del \u00a0testimonio \u00a0supuestamente \u00a0falseado, \u00a0para \u00a0compararlo \u00a0con \u00a0las \u00a0atestaciones \u00a0que aqu\u00e9l realmente hizo bajo juramento, ejercicio con el cual se \u00a0habr\u00eda puesto en evidencia el yerro denunciado.\u00a0 \u00a0\u00a0<\/p>\n<p>Pero \u00a0la \u00a0demanda no s\u00f3lo defecciona por la \u00a0falta \u00a0de \u00a0coherencia \u00a0l\u00f3gica en la proposici\u00f3n del cargo y por la ausencia de \u00a0fundamentaci\u00f3n \u00a0 del \u00a0 mismo, \u00a0 sino \u00a0 porque \u00a0 adem\u00e1s \u00a0 olvida \u00a0demostrar \u00a0la \u00a0trascendencia \u00a0que \u00a0pod\u00edan \u00a0tener los errores probatorios denunciados, cometido \u00a0este \u00a0que \u00a0le \u00a0impon\u00eda\u00a0 \u00a0al \u00a0demandante \u00a0la \u00a0carga de examinar el conjunto \u00a0probatorio \u00a0tenido \u00a0en \u00a0cuenta \u00a0por \u00a0el sentenciador para fundar la condena, con \u00a0excepci\u00f3n \u00a0de \u00a0los \u00a0medios \u00a0afectados \u00a0por \u00a0el \u00a0vicio \u00a0arg\u00fcido, \u00a0para \u00a0ver \u00a0de \u00a0establecer \u00a0si sin \u00e9stos el fallo adverso al acusado manten\u00eda sustento o, como \u00a0es \u00a0la \u00a0pretensi\u00f3n \u00a0de \u00a0la \u00a0demanda, \u00a0deb\u00eda \u00a0quebrarse \u00a0para \u00a0dar \u00a0paso \u00a0a \u00a0la \u00a0absoluci\u00f3n. \u00a0\u00a0<\/p>\n<p>En \u00a0raz\u00f3n \u00a0de \u00a0las \u00a0falencias que vienen de \u00a0analizarse, \u00a0se \u00a0impone \u00a0la \u00a0inadmisi\u00f3n \u00a0de \u00a0la \u00a0demanda \u00a0como \u00a0lo \u00a0previene el \u00a0art\u00edculo \u00a0213 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0dando \u00a0paso\u00a0 \u00a0a la \u00a0declaratoria \u00a0 de \u00a0 deserci\u00f3n \u00a0 del \u00a0 recurso \u00a0 por \u00a0carecer \u00a0de \u00a0una \u00a0adecuada \u00a0sustentaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0expuesto,\u00a0 LA CORTE SUPREMA DE \u00a0JUSTICIA, SALA DE CASACION PENAL, \u00a0\u00a0<\/p>\n<p>R E S U E L V E \u00a0<\/p>\n<p>Inadmitir la demanda de casaci\u00f3n presentada \u00a0por \u00a0el \u00a0defensor \u00a0del procesado JOSE GREGORIO RAMIREZ MENDOZA; en consecuencia, \u00a0se declara desierto el recurso interpuesto. \u00a0\u00a0<\/p>\n<p>Contra \u00a0 este \u00a0 auto \u00a0no \u00a0procede \u00a0recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, c\u00famplase y devu\u00e9lvase al Tribunal \u00a0de origen. \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0EDUARDO \u00a0MEJ\u00cdA \u00a0ESCOBAR \u00a0\u00a0<\/p>\n<p>FERNANDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 ARBOLEDA \u00a0RIPOLL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JORGE E. C\u00d3RDOBA POVEDA \u00a0\u00a0<\/p>\n<p>HERMAN \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0GAL\u00c1N \u00a0CASTELLANOS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0CARLOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 A. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0G\u00c1LVEZ \u00a0ARGOTE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JORGE \u00a0 \u00a0 \u00a0 \u00a0AN\u00cdBAL \u00a0 \u00a0 \u00a0 G\u00d3MEZ \u00a0GALLEGO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0EDGAR LOMBANA TRUJILLO \u00a0\u00a0<\/p>\n<p>ALVARO \u00a0 \u00a0 \u00a0ORLANDO \u00a0 \u00a0 \u00a0P\u00c9REZ \u00a0PINZON\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0NILSON PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>TERESA RUIZ NU\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 16332 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0Magistrado \u00a0Ponente \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Dr. JORGE ANIBAL GOMEZ GALLEGO \u00a0\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4424","post","type-post","status-publish","format-standard","hentry","category-9"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/4424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=4424"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/4424\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=4424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=4424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=4424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}