{"id":44089,"date":"2023-09-14T21:49:05","date_gmt":"2023-09-14T21:49:05","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/14\/atp613-2019\/"},"modified":"2023-09-14T21:49:05","modified_gmt":"2023-09-14T21:49:05","slug":"atp613-2019","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/14\/atp613-2019\/","title":{"rendered":"ATP613-2019"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>LUIS GUILLERMO \u00a0SALAZAR OTERO \u00a0<\/p>\n<p>Magistrado \u00a0ponente \u00a0<\/p>\n<p>ATP613-2019 \u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0n\u00b0 103746 \u00a0<\/p>\n<p>Acta \u00a096 \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D.C., once (11) de abril de dos mil diecinueve (2019). \u00a0<\/p>\n<p>I. \u00a0VISTOS \u00a0<\/p>\n<p>Ser\u00eda del \u00a0caso pronunciarse de fondo sobre la impugnaci\u00f3n presentada \u00a0por el apoderado de \u00a0Jhon \u00a0Harrison Estupi\u00f1\u00e1n Paz, \u00a0contra el fallo proferido el 21 de febrero del a\u00f1o en curso, \u00a0por la Sala \u00a0Penal del Tribunal Superior del Distrito Judicial de Cali, \u00a0quien \u00a0declar\u00f3 improcedente la acci\u00f3n de tutela interpuesta en \u00a0protecci\u00f3n del derecho fundamental al debido proceso, \u00a0presuntamente vulnerado por el Juzgado \u00a011 Penal del Circuito con Funciones de Conocimiento de esa ciudad, \u00a0de no ser porque se advierte una causal de nulidad que hace necesario \u00a0invalidar la actuaci\u00f3n. \u00a0<\/p>\n<p>II. HECHOS Y \u00a0FUNDAMENTOS DE LA ACCI\u00d3N \u00a0<\/p>\n<p>Los \u00a0sucesos que motivaron la solicitud de amparo constitucional y las \u00a0pretensiones del actor fueron rese\u00f1ados por el A \u00a0quo \u00a0en los siguientes t\u00e9rminos: \u00a0<\/p>\n<p>El \u00a0apoderado del se\u00f1or JHON HARRISON ESTUPI\u00d1AN PAZ, \u00a0interpone ACCION DE TUETLA, en contra de la Sentencia No.014 de marzo \u00a08 de 2016 proferida por el JUZGADO 11 PENAL DEL CIRCUITO CON \u00a0FUNCIONES DE CONOCIMIENTO DE CALI, por la presunta vulneraci\u00f3n \u00a0del derecho fundamental al debido proceso de su asistido. \u00a0<\/p>\n<p>En \u00a0efecto, aduce que para la calenda en que se emiti\u00f3 dicha \u00a0decisi\u00f3n, la acci\u00f3n penal que se le adelantaba a su \u00a0prohijado, se encontraba prescrita, ya que la denuncia se present\u00f3 \u00a0el 4 de mayo de 2009 y la sentencia condenatoria se emiti\u00f3 el \u00a08 de marzo de 2016, termino este, que seg\u00fan el actor, supera \u00a0el interregno dispuesto en el art\u00edculo 83 del C\u00f3digo \u00a0Penal. \u00a0<\/p>\n<p>Adem\u00e1s, \u00a0se\u00f1ala que la Operadora Judicial no valor\u00f3 la \u00a0conciliaci\u00f3n efectuada entre el acusado JHON HARRISON \u00a0ESTUPI\u00d1AN PAZ y el Gerente General del Establecimiento \u00a0COMERCIAL FERRASA S.A., por lo que no se dio aplicaci\u00f3n a la \u00a0respectiva rebaja de pena contemplada en la Ley, a pesar de haber \u00a0reparado los perjuicios causados a la v\u00edctima. \u00a0<\/p>\n<p>De \u00a0ese modo, luego de cuestionar la pena impuesta por el JUZGADO 11 \u00a0PENAL DEL CIRCUITO CON FUNCIONES DE CONOCIMIENTO DE CALI, solicita la \u00a0revocatoria de dicha decisi\u00f3n y que, como como consecuencia, \u00a0se le conceda el subrogado de la suspensi\u00f3n condicional de la \u00a0ejecuci\u00f3n de la pena o prisi\u00f3n domiciliaria, \u201cpor \u00a0ser un ciudadano sin antecedentes y su familia haber reparado a la \u00a0empresa victima FERRASA S.A., hoy TERNIUIM (CO), quien se mostr\u00f3 \u00a0satisfecha con lo acordado y pagado. \u00a0<\/p>\n<p>III. \u00a0DEL FALLO RECURRIDO \u00a0<\/p>\n<p>La \u00a0Sala Penal del Tribunal Superior de Cali declar\u00f3 improcedente \u00a0la acci\u00f3n interpuesta, con fundamento en que no se advert\u00eda \u00a0la configuraci\u00f3n de los requisitos, tanto generales como \u00a0espec\u00edficos, exigidos para la procedencia de la misma, tales \u00a0como la subsidiariedad y la inmediatez, adem\u00e1s de la \u00a0inobservancia de defecto sustantivo que hiciere necesaria la \u00a0intervenci\u00f3n excepcional del juez constitucional. \u00a0<\/p>\n<p>Conforme \u00a0a ello, rese\u00f1\u00f3 que contra la sentencia de primera \u00a0instancia no se interpuso recurso alguno, quedando \u00e9sta \u00a0debidamente ejecutoriada, adem\u00e1s de que la presente tutela se \u00a0present\u00f3 mucho tiempo despu\u00e9s de su firmeza sin \u00a0justificaci\u00f3n alguna, m\u00e1xime si se considera que el hoy \u00a0apoderado del actor fue el mismo abogado que lo asisti\u00f3 \u00a0durante el decurso procesal. \u00a0<\/p>\n<p>De \u00a0igual forma precis\u00f3 que, si en gracia a discusi\u00f3n, se \u00a0admitiera la tesis de la prescripci\u00f3n de la acci\u00f3n \u00a0penal, el mecanismo adecuado para dirimir dicha controversia seria la \u00a0acci\u00f3n de revisi\u00f3n, la cual ya fue presentada en una \u00a0oportunidad, sin embargo se rechaz\u00f3 de plano, sin que sea \u00a0entonces viable pretender, mediante la presente demanda de amparo, \u00a0controvertir la decisi\u00f3n condenatoria. \u00a0<\/p>\n<p>IV. \u00a0DE LA IMPUGNACI\u00d3N \u00a0<\/p>\n<p>Fue \u00a0presentada por el apoderado de Jhon \u00a0Harrison Estupi\u00f1\u00e1n Paz, \u00a0quien sustent\u00f3 \u00a0el disenso sobre el mismo recuento f\u00e1ctico expuesto en la \u00a0acci\u00f3n tuitiva; y reiter\u00f3 sus argumentos con la \u00a0finalidad de lograr la protecci\u00f3n del derecho al debido \u00a0proceso que estima vulnerado. \u00a0<\/p>\n<p>V. \u00a0CONSIDERACIONES \u00a0<\/p>\n<p>1. \u00a0Ser\u00eda \u00a0el caso que la Sala se ocupara de resolver la impugnaci\u00f3n \u00a0interpuesta por Jhon \u00a0Harrison Estupi\u00f1\u00e1n Paz, \u00a0sin \u00a0embargo, se advierte la existencia de una causal de nulidad que \u00a0invalida la actuaci\u00f3n porque no se conform\u00f3 en debida \u00a0forma el contradictorio. \u00a0<\/p>\n<p>2. En reiteradas \u00a0oportunidades, la jurisprudencia de la Sala (CSJ \u00a0ATP, 19 jun.2018, rad. 98945; CSJ ATP, 14 jun. 2018, rad 98712; CSJ \u00a0ATP, 31 may. 2018, rad. 98419, entre otras) \u00a0ha sostenido que, pese al deber del accionante de manifestar cu\u00e1l \u00a0es la autoridad o el particular que ha lesionado o amenazado sus \u00a0derechos, tal enunciaci\u00f3n no puede atar al juez \u00a0constitucional, ni limitar su \u00e1mbito de gesti\u00f3n, pues \u00a0al juzgador le corresponde revisar la situaci\u00f3n que se tacha \u00a0de irregular y vincular a todas las personas y entidades que pueden \u00a0estar vulnerando las garant\u00edas reclamadas, as\u00ed como a \u00a0aquellos que habr\u00edan de verse afectados con la decisi\u00f3n \u00a0que se adopte al resolver la petici\u00f3n de amparo propuesta. \u00a0<\/p>\n<p>3. En el sub \u00a0lite, \u00a0la acci\u00f3n de tutela se dirige contra la sentencia condenatoria \u00a0emitida el 8 de marzo de 2016 por el Juzgado 11 Penal del Circuito \u00a0con Funciones de Conocimiento de Cali, dentro del proceso \u00a0No.76892600191200900234 seguido contra Jhon \u00a0Harrison Estupi\u00f1\u00e1n Paz, \u00a0por \u00a0el delito de hurto agravado en concurso homog\u00e9neo y sucesivo, \u00a0en concurso heterog\u00e9neo con falsedad en documento privado en \u00a0concurso homog\u00e9neo y sucesivo, al considerar el apoderado el \u00a0sentenciado, que no se realiz\u00f3 la rebaja de pena \u00a0correspondiente en virtud de la reparaci\u00f3n de perjuicios, y \u00a0adem\u00e1s, la \u00a0providencia se emiti\u00f3 estando prescrita la acci\u00f3n. \u00a0<\/p>\n<p>4. La Sala Penal \u00a0del Tribunal Superior del Distrito Judicial de Cali, en el auto del \u00a011 de febrero del presente a\u00f1o, mediante el cual avoc\u00f3 \u00a0el conocimiento de la acci\u00f3n de tutela, de las personas que \u00a0integraban los extremos dentro del proceso penal, orden\u00f3 \u00a0vincular \u00fanicamente al Juzgado de conocimiento. \u00a0<\/p>\n<p>5. Sin embargo, no \u00a0dispuso el llamado del Establecimiento Comercial FERRASA S.A., en \u00a0calidad de v\u00edctima, quien mediante apoderado interpuso la \u00a0respectiva denuncia, activando as\u00ed el \u00a0\u00f3rgano persecutor y por tanto, llamado a sentar su postura \u00a0sobre las refutaciones desplegadas por el defensor contra el fallo \u00a0condenatorio. \u00a0<\/p>\n<p>6. \u00a0Igualmente se tornaba necesario informar al delegado del ente \u00a0acusador que estuvo a cargo del asunto, esto es, la Fiscal\u00eda \u00a0156 Seccional de Yumbo \u2013Valle del Cauca-, como tambi\u00e9n \u00a0al delegado del Ministerio P\u00fablico que conoci\u00f3 del \u00a0proceso, siendo estas partes a las cuales les interesa las resultas \u00a0del presente asunto. \u00a0<\/p>\n<p>7. Conforme a lo \u00a0anterior, es necesario precisar que los art\u00edculos 16 del \u00a0Decreto 2591 de 1991 y 5 del Decreto 306 de 1992, surge como \u00a0requisito de procedimiento que tanto la iniciaci\u00f3n, como las \u00a0decisiones adoptadas en el \u00ab(\u2026) \u00a0tr\u00e1mite \u00a0de una acci\u00f3n de tutela se deber\u00e1n notificar a las \u00a0partes o a los intervinientes. Para este efecto, son partes la \u00a0persona que ejerce la acci\u00f3n de tutela y el particular, la \u00a0entidad o autoridad p\u00fablica contra la cual se dirige la acci\u00f3n \u00a0de tutela\u00bb. \u00a0<\/p>\n<p>8. De la misma \u00a0manera, el juez \u00a0\u00abvelar\u00e1 porque de acuerdo con las circunstancias, el \u00a0medio y la oportunidad de la notificaci\u00f3n aseguren la eficacia \u00a0de la misma y la posibilidad de ejercer el derecho de defensa\u00bb. \u00a0<\/p>\n<p>9. La obligaci\u00f3n \u00a0de enterar a los demandados de la acci\u00f3n instaurada en su \u00a0contra y a los terceros que puedan resultar perjudicados con el \u00a0fallo, dimana del mandato legal y de la doctrina constitucional. Esta \u00a0\u00faltima, por ejemplo, ha establecido, a trav\u00e9s de \u00a0pronunciamiento CC T -293-1994, que: \u00a0<\/p>\n<p>\u00abUna \u00a0vez formulada la petici\u00f3n de tutela debe iniciarse el \u00a0procedimiento correspondiente y el juez debe buscar \u2013con miras \u00a0a la garant\u00eda del debido proceso\u2014 que se notifique, \u00a0acerca de la acci\u00f3n instaurada, a aqu\u00e9l contra quien \u00a0ella se endereza. As\u00ed lo ha dispuesto el Decreto 2591 de 1991 \u00a0en su art\u00edculo 16\u00bb. \u00a0<\/p>\n<p>Y ha agregado que: \u00a0<\/p>\n<p>\u00abEl \u00a0objeto de tal notificaci\u00f3n es el de asegurar la defensa de la \u00a0autoridad o del particular contra quien act\u00faa el peticionario \u00a0y la protecci\u00f3n procesal de los intereses de terceros que \u00a0puedan verse afectados con la decisi\u00f3n. \u00a0<\/p>\n<p>En \u00a0cuanto alude espec\u00edficamente a la persona sindicada de violar \u00a0o amenazar derechos fundamentales, debe tener la oportunidad de dar \u00a0sus razones e inclusive de desvirtuar lo afirmado en su contra. \u00a0<\/p>\n<p>Reitera \u00a0la Corte que, cuando se establezca sin lugar a dudas que la sentencia \u00a0de tutela ha sido proferida por el juez sin hacer el menor esfuerzo \u00a0por facilitar el acceso del demandado a la actuaci\u00f3n procesal \u00a0para los fines de su defensa, es decir, cuando el fallador ha \u00a0preferido conformarse con conocer tan solo una de las versiones \u2013la \u00a0de la parte actora-, sin cuidarse de procurar el conocimiento de lo \u00a0que tenga que decir aquel contra quien se act\u00faa, hay una clara \u00a0violaci\u00f3n al debido proceso y la consecuencia de ella no puede \u00a0ser otra que la nulidad de lo que, sobre la base de ese vicio, se ha \u00a0adelantado procesalmente\u00bb. \u00a0<\/p>\n<p>10. En s\u00edntesis, \u00a0la actuaci\u00f3n surtida en primera instancia comporta un defecto \u00a0procedimental, en virtud del cual no sobreviene alternativa distinta \u00a0para esta Sala de Decisi\u00f3n de Tutelas que la de decretar la \u00a0nulidad de lo actuado por el juez constitucional, a \u00a0partir del fallo de primera instancia emitido el 21 de febrero de \u00a02019, a \u00a0fin de que se tramite y profiera la decisi\u00f3n que corresponda \u00a0con respeto de las garant\u00edas fundamentales incoadas. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la Sala \u00a0de Decisi\u00f3n de Tutelas N\u00ba 3 de la Sala de Casaci\u00f3n \u00a0Penal de la Corte Suprema de Justicia, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>PRIMERO: \u00a0Declarar la nulidad de lo actuado por la \u00a0Sala de Penal del Tribunal Superior del Distrito Judicial de Cali, \u00a0a partir del \u00a0fallo emitido el 21 de febrero de 2019, \u00a0para \u00a0que se vincule al \u00a0Establecimiento Comercial FERRASA S.A., a \u00a0la Fiscal\u00eda 156 Seccional de Yumbo \u2013Valle del Cauca- y \u00a0al delegado del Ministerio P\u00fablico que conoci\u00f3 del \u00a0proceso. \u00a0<\/p>\n<p>SEGUNDO: \u00a0Notificar esta decisi\u00f3n en la forma prevista por el Decreto \u00a02591 de 1991 y devu\u00e9lvanse las diligencias al Tribunal de \u00a0origen para que rehaga el procedimiento de acuerdo con la parte \u00a0motiva de esta decisi\u00f3n. \u00a0<\/p>\n<p>Comun\u00edquese \u00a0y c\u00famplase, \u00a0<\/p>\n<p>LUIS \u00a0GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>EYDER \u00a0PATI\u00d1O CABRERA \u00a0<\/p>\n<p>NUBIA \u00a0YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 LUIS GUILLERMO \u00a0SALAZAR OTERO \u00a0 Magistrado \u00a0ponente \u00a0 ATP613-2019 \u00a0 Radicaci\u00f3n \u00a0n\u00b0 103746 \u00a0 Acta \u00a096 \u00a0 Bogot\u00e1, \u00a0D.C., once (11) de abril de dos mil diecinueve (2019). \u00a0 I. \u00a0VISTOS \u00a0 Ser\u00eda del \u00a0caso pronunciarse de fondo sobre la impugnaci\u00f3n presentada \u00a0por el apoderado de \u00a0Jhon \u00a0Harrison Estupi\u00f1\u00e1n Paz, \u00a0contra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-44089","post","type-post","status-publish","format-standard","hentry","category-28"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/44089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=44089"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/44089\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=44089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=44089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=44089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}