{"id":43370,"date":"2023-09-14T21:44:10","date_gmt":"2023-09-14T21:44:10","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/14\/ap671-201952628\/"},"modified":"2023-09-14T21:44:10","modified_gmt":"2023-09-14T21:44:10","slug":"ap671-201952628","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/14\/ap671-201952628\/","title":{"rendered":"AP671-2019(52628)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>EYDER \u00a0PATI\u00d1O CABRERA \u00a0<\/p>\n<p>Magistrado \u00a0Ponente \u00a0<\/p>\n<p>AP671-2019 \u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0n\u00b0.52628 \u00a0<\/p>\n<p>(Aprobado \u00a0acta n\u00b0. 52) \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D.C., veintisiete (27) de febrero de dos mil diecinueve (2019). \u00a0<\/p>\n<p>MOTIVO \u00a0DE LA DECISI\u00d3N \u00a0<\/p>\n<p>Decide \u00a0la Sala si es procedente admitir la demanda de casaci\u00f3n \u00a0presentada por el defensor de Harold \u00a0Smith Cort\u00e9s S\u00e1ez, \u00a0contra la sentencia proferida el 16 de febrero de 2018 por el \u00a0Tribunal Superior de Bogot\u00e1, que confirm\u00f3 el fallo \u00a0dictado por el Juzgado Treinta Penal del Circuito de esta ciudad y \u00a0conden\u00f3 al procesado como autor del delito de fabricaci\u00f3n, \u00a0tr\u00e1fico, porte o tenencia de armas de fuego. \u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>El \u00a0Tribunal resumi\u00f3 el aspecto f\u00e1ctico, conforme fue \u00a0narrado por el fallador de primera instancia: \u00a0<\/p>\n<p>Acorde \u00a0a las pruebas practicadas y aportadas a la audiencia de juicio oral, \u00a0se conoci\u00f3 que en horas de la madrugada del pasado 2 de marzo \u00a0de 2012, a la altura de la carrera 68 G con calle 38 de esta ciudad \u00a0 [Bogot\u00e1] \u00a0en \u00a0v\u00eda p\u00fablica, en momentos en que el ciudadano Ciro \u00a0Alfonso Rey Becerra se encontraba ejerciendo labores de recolecci\u00f3n \u00a0de basuras, como empleado de la empresa Casa Limpia, fue herido por \u00a0un proyectil de arma de fuego a la altura de su cintura, mientras iba \u00a0colgado en la parte de atr\u00e1s del cami\u00f3n dise\u00f1ado \u00a0para ese tipo de tareas. \u00a0<\/p>\n<p>Al \u00a0arribar uniformados (sic), \u00a0que fueron advertidos de lo acaecido, se entrevistaron con un testigo \u00a0directo de los hechos, quien les se\u00f1al\u00f3 el sitio en \u00a0donde se ubicaba el individuo que instantes antes hab\u00eda \u00a0realizado los disparos que produjeron las lesiones del herido, \u00a0procedi\u00e9ndose entonces, con la aprehensi\u00f3n de quien \u00a0despu\u00e9s fue identificado como Harold Smith Cort\u00e9s S\u00e1ez, \u00a0pues al notar la presencia policial, arroj\u00f3 un objeto, que se \u00a0detect\u00f3 instantes despu\u00e9s, era un arma frente a la cual \u00a0no se exhibi\u00f3 permiso para su porte1. \u00a0<\/p>\n<p>ACTUACI\u00d3N \u00a0PROCESAL \u00a0<\/p>\n<p>1. \u00a0El 3 de marzo de 2012, ante el Juzgado Cincuenta y Dos Penal \u00a0Municipal con funci\u00f3n de control de garant\u00edas-URI \u00a0Kennedy, se llev\u00f3 a cabo audiencia preliminar de legalizaci\u00f3n \u00a0de captura, formulaci\u00f3n de imputaci\u00f3n contra Harold \u00a0Smith Cort\u00e9s S\u00e1ez, \u00a0por \u00a0el delito de homicidio tentado en concurso con fabricaci\u00f3n, \u00a0tr\u00e1fico, porte o tenencia de armas de fuego, previstos en los \u00a0art\u00edculos 103, 27 y 365 del C\u00f3digo Penal, e imposici\u00f3n \u00a0de medida de aseguramiento de detenci\u00f3n preventiva en el lugar \u00a0de residencia2. \u00a0<\/p>\n<p>2. \u00a0Radicado el escrito de acusaci\u00f3n3, \u00a0su formulaci\u00f3n se realiz\u00f3 el 27 de junio siguiente, \u00a0bajo la direcci\u00f3n del Juzgado Segundo Penal del Circuito con \u00a0funciones de conocimiento de Bogot\u00e14. \u00a0<\/p>\n<p>3. \u00a0La audiencia preparatoria, despu\u00e9s de muchos aplazamientos, \u00a0tuvo lugar el 12 de agosto de 20135, \u00a0y la de juicio oral el 17 de septiembre de 2014, fecha en que se \u00a0anunci\u00f3 el sentido de fallo de car\u00e1cter absolutorio6. \u00a0<\/p>\n<p>4. \u00a0En la misma calenda, el juez de conocimiento dict\u00f3 la \u00a0sentencia correspondiente, por cuyo medio absolvi\u00f3 a Harold \u00a0Smith Cort\u00e9s S\u00e1ez de \u00a0los cargos que por los delitos de homicidio tentado y fabricaci\u00f3n, \u00a0tr\u00e1fico, porte o tenencia de armas de fuego, accesorios, \u00a0partes o municiones, le formul\u00f3 la Fiscal\u00eda7. \u00a0<\/p>\n<p>5. \u00a0El 6 de agosto de 2015, el Tribunal Superior de Bogot\u00e1, al \u00a0resolver el recurso de apelaci\u00f3n incoado por los \u00a0representantes de la Fiscal\u00eda y del Ministerio P\u00fablico, \u00a0decret\u00f3 la nulidad parcial de lo actuado, desde la sesi\u00f3n \u00a0de juicio oral llevada a cabo el 17 de septiembre de 2014, \u00a0concretamente, desde el momento en que se declar\u00f3 cerrada la \u00a0etapa probatoria, con el fin de que se reinstale la diligencia, de \u00a0modo que la Fiscal\u00eda General de la Naci\u00f3n pueda hacer \u00a0comparecer, por alguno de los medios leg\u00edtimos admisibles, \u00a0a \u00a0varios testigos8. \u00a0<\/p>\n<p>6. \u00a0Una vez el expediente regres\u00f3 al despacho de primera \u00a0instancia, su titular se declar\u00f3 impedido, manifestaci\u00f3n \u00a0que fue admitida por el Juez Treinta Penal del Circuito de esta \u00a0capital, quien, en obedecimiento de lo dispuesto por el Tribunal, \u00a0program\u00f3 la audiencia de juicio oral, la cual se llev\u00f3 \u00a0a cabo en sesiones del 25 de noviembre de 20169, \u00a026 de enero y 4 de julio de 201710. \u00a0<\/p>\n<p>7. \u00a0El 30 de agosto siguiente, el funcionario anunci\u00f3 el sentido \u00a0del fallo11 \u00a0y, consecuente con el mismo, el 1\u00ba de septiembre posterior \u00a0resolvi\u00f3 precluir la investigaci\u00f3n adelantada contra \u00a0Harold \u00a0Smith Cortes S\u00e1ez respecto \u00a0del delito de lesiones personales culposas12, \u00a0(seg\u00fan estipulaci\u00f3n probatoria, al ofendido se le \u00a0dictamin\u00f3 incapacidad de setenta (70) d\u00edas y, como \u00a0secuelas, deformidad f\u00edsica de car\u00e1cter permanente) \u00a0respecto del cual declar\u00f3 la prescripci\u00f3n de la acci\u00f3n \u00a0penal y ces\u00f3 procedimiento. \u00a0<\/p>\n<p>En \u00a0tanto que, conden\u00f3 al procesado como autor del injusto de \u00a0fabricaci\u00f3n, tr\u00e1fico, porte o tenencia de armas de \u00a0fuego, accesorios, partes o municiones, a la pena de nueve (9) a\u00f1os \u00a0de prisi\u00f3n y a las accesorias de inhabilitaci\u00f3n para el \u00a0ejercicio de derechos y funciones p\u00fablicas, por tiempo igual a \u00a0la sanci\u00f3n principal, y la privaci\u00f3n del derecho a la \u00a0tenencia y porte de armas de fuego por el t\u00e9rmino de doce (12) \u00a0meses. \u00a0<\/p>\n<p>Le \u00a0neg\u00f3 la suspensi\u00f3n condicional de la ejecuci\u00f3n \u00a0de la pena y la prisi\u00f3n domiciliaria y, finalmente, orden\u00f3 \u00a0el comiso del arma de fuego, tipo pistola, marca browing, con n\u00famero \u00a072R20301, calibre 7.65 mm, a favor del Comando General de las Fuerzas \u00a0Militares13. \u00a0<\/p>\n<p>8. \u00a0El 16 de febrero de 2018, el Tribunal Superior de Bogot\u00e1, al \u00a0conocer del recurso de apelaci\u00f3n incoado por la defensa, \u00a0confirm\u00f3 en su integridad la decisi\u00f3n del A \u00a0quo14. \u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>El libelista \u00a0identifica las partes e intervinientes, la sentencia impugnada, los \u00a0hechos y la actuaci\u00f3n procesal, y aduce, respecto de las \u00a0finalidades del recurso, que en este caso se afectaron garant\u00edas \u00a0fundamentales, conforme a los lineamientos del art\u00edculo 29 de \u00a0la Constituci\u00f3n Pol\u00edtica, en asocio con los preceptos \u00a07\u00ba y 8\u00ba de la Ley 906 de 2004. \u00a0<\/p>\n<p>A continuaci\u00f3n, \u00a0formula dos cargos, as\u00ed: \u00a0<\/p>\n<p>Primero \u00a0(principal): \u00a0nulidad. \u00a0<\/p>\n<p>Con sustento en la \u00a0causal segunda, reprocha el desconocimiento del debido proceso, por \u00a0afectaci\u00f3n sustancial de su estructura o de la garant\u00eda \u00a0a cualquiera de las partes. \u00a0<\/p>\n<p>Recuerda que en el \u00a0desarrollo de la actuaci\u00f3n, el juez colegiado revis\u00f3 el \u00a0presente asunto en dos oportunidades; la primera, cuando decret\u00f3 \u00a0la nulidad de todo lo actuado y devolvi\u00f3 el asunto al despacho \u00a0de conocimiento para que se practicaran las pruebas solicitadas por \u00a0el delegado de la Fiscal\u00eda, decisi\u00f3n que la defensa no \u00a0aval\u00f3, sino que no la recurri\u00f3 porque contra ella no \u00a0proced\u00edan recursos legales. \u00a0<\/p>\n<p>Por esa raz\u00f3n, \u00a0explica, no le queda otro camino que pronunciarse \u00aben \u00a0el contexto de la apelaci\u00f3n actual\u00bb, \u00a0donde afirma su posici\u00f3n en cuanto a la preclusividad de los \u00a0t\u00e9rminos en el procedimiento oral y que no se puede recargar a \u00a0una de las partes hasta que se practiquen las pruebas de la otra \u00abas\u00ed \u00a0el tiempo sea ilimitado que es lo que pas\u00f3 en este asunto\u00bb. \u00a0<\/p>\n<p>Luego de advertir \u00a0que atiende a los principios de taxatividad y trascendencia de las \u00a0nulidades, dado que se trata de un hecho que afect\u00f3 el debido \u00a0proceso, al existir dilaciones injustificadas, asevera que el \u00a0Tribunal se tom\u00f3 un tiempo extremadamente largo para adoptar \u00a0\u00abla \u00a0decisi\u00f3n que ahora nos ocupa\u00bb y \u00a0que el Juez Segundo Penal del Circuito ya hab\u00eda \u00abdeterminado \u00a0unos t\u00e9rminos de preclusividad de la pr\u00e1ctica de \u00a0pruebas en el juicio oral\u00bb y \u00a0le hab\u00eda dado un plazo razonable a la Fiscal\u00eda para \u00a0recaudar el testimonio de Diego \u00a0Giovanny Forero Dom\u00ednguez, quien \u00a0solo apareci\u00f3 despu\u00e9s de cinco (5) a\u00f1os de \u00a0ocurridos los hechos. \u00a0<\/p>\n<p>Esa declaraci\u00f3n, \u00a0que afect\u00f3 los intereses del procesado, \u00a0\u00abes \u00a0un acto procesal fundamental que cercena la inocencia del mismo, ya \u00a0que despu\u00e9s de tanto tiempo de no ser escuchado el testimonio, \u00a0ello dio a adoptar una posici\u00f3n de importancia al ser \u00a0condenado\u00bb. \u00a0<\/p>\n<p>Opina que el fallo \u00a0debi\u00f3 proferirse con lo recaudado hasta el momento en que el \u00a0Juez Segundo Penal del Circuito clausur\u00f3 el debate probatorio \u00a0\u00ab \u00a0y no en este momento procesal a instancias del Juzgado 30 Penal del \u00a0Circuito y de la nueva decisi\u00f3n adoptada por el Tribunal, \u00a0admitiendo una dilaci\u00f3n injustificada de los t\u00e9rminos \u00a0para favorecer a como d\u00e9 lugar a una de las partes \u00a0(fiscal\u00eda)\u00bb. \u00a0<\/p>\n<p>Invoca como \u00a0desconocidos los art\u00edculos 4\u00ba y 8\u00ba, literal k), 16 y \u00a017 de la Ley 906 de 2004 y reitera que pretende la reparaci\u00f3n \u00a0del da\u00f1o causado, quit\u00e1ndole efectos a la decisi\u00f3n \u00a0del Tribunal que decret\u00f3 la nulidad, para que se dicte fallo \u00a0con la carga probatoria existente para ese momento, cuando no se \u00a0hab\u00eda recaudado la declaraci\u00f3n de Diego \u00a0Giovanny Forero Dom\u00ednguez, \u00a0ya que con ello se afect\u00f3 la inocencia del procesado. \u00a0<\/p>\n<p>El censor, aparte \u00a0de insistir en los mismos argumentos, exalta la actuaci\u00f3n del \u00a0Juez Segundo Penal del Circuito al delimitar el comportamiento de los \u00a0sujetos procesales, porque fuera de varias convocatorias, logr\u00f3 \u00a0obtener m\u00e1s del 90% de pruebas en el juicio, \u00aby \u00a0la insistencia del se\u00f1or Fiscal para un momento de efectos \u00a0inmediatos nunca se dio, ya que la declaraci\u00f3n del testigo que \u00a0presuntamente observ\u00f3 el hecho apareci\u00f3 despu\u00e9s \u00a0de dos (2) a\u00f1os, en un letargo admitido por la judicatura \u00a0injustamente\u00bb , \u00a0al punto que se le da credibilidad despu\u00e9s que su memoria de \u00a0los hechos ha sido afectada y se logra una condena solo por la forma \u00a0como estaba vestido el procesado y no por sus rasgos f\u00edsicos. \u00a0<\/p>\n<p>Insiste en que ese \u00a0acto de dilaci\u00f3n en el tiempo \u00aby \u00a0con una percepci\u00f3n ambivalente de hechos del testigo \u00a0estrella\u00bb, \u00a0afecta ostensiblemente el debido proceso y que no se puede esperar a \u00a0que la contraparte aporte sus testigos, m\u00e1xime cuando existen \u00a0medios coercitivos y sancionatorios para encontrar la efectividad de \u00a0la justicia. \u00a0<\/p>\n<p>Solicita se case \u00a0la sentencia de segunda instancia y, en su lugar, se declare la \u00a0nulidad de lo actuado desde la decisi\u00f3n proferida por el \u00a0Tribunal el 6 de agosto de 2015 y, en su lugar, emita fallo \u00a0definitivo con lo hasta all\u00ed aportado, \u00abde \u00a0absoluci\u00f3n o condena a favor del procesado\u00bb. \u00a0<\/p>\n<p>Segundo \u00a0(subsidiario). \u00a0<\/p>\n<p>Por la v\u00eda \u00a0de la violaci\u00f3n indirecta de la ley, acusa un error de hecho \u00a0por falso raciocinio, que fundamenta as\u00ed: \u00a0<\/p>\n<p>El Tribunal hizo \u00a0una valoraci\u00f3n probatoria equ\u00edvoca, cuando infiri\u00f3 \u00a0que no existe contradicci\u00f3n entre las narraciones \u2013que \u00a0previamente transcribe- del \u00a0empleado \u00a0de la empresa de aseo Ciudad Limpia Diego \u00a0Giovanny Forero \u00a0y el agente de polic\u00eda Oscar \u00a0Orlando Castro Ram\u00edrez, pues, \u00a0explica, una persona no puede estar en determinado sitio libando \u00a0licor y a su vez caminando en forma r\u00e1pida. \u00a0<\/p>\n<p>No es posible \u00a0indicar que una persona se puede encontrar en un lugar y por la calle \u00a0caminando, presuntamente tirando un objeto, porque, seg\u00fan el \u00a0patrullero, el sitio de la calle no era tan claro para se\u00f1alar \u00a0que dicha persona estaba en la esquina como si nada hubiera pasado. \u00a0<\/p>\n<p>Empero, para el \u00a0juez corporativo se trata de una imprecisi\u00f3n que en nada \u00a0desdibuja el relato de los mencionados, sin tener en cuenta el \u00a0desarrollo jurisprudencial y que el yerro acusado recae sobre los \u00a0principios de la l\u00f3gica, las m\u00e1ximas de la experiencia \u00a0o los postulados de la ciencia. \u00a0<\/p>\n<p>En el campo de la \u00a0l\u00f3gica, los jueces tienen la obligaci\u00f3n de acatar el \u00a0principio de raz\u00f3n suficiente a la hora de motivar sus \u00a0decisiones, por lo cual, los hechos \u00abtrazados \u00a0en el fallo de primera y segunda instancia son equ\u00edvocos y por \u00a0ende de dudosa aplicaci\u00f3n en un fallo de condena\u00bb, \u00a0m\u00e1xime cuando el art\u00edculo 403-6 de la Ley 906 de 2004 \u00a0prev\u00e9 que la impugnaci\u00f3n de un testigo se advierte \u00a0cuando existe contradicciones en el contenido de la declaraci\u00f3n. \u00a0<\/p>\n<p>Conforme a las \u00a0m\u00e1ximas de la experiencia no se puede aceptar que las dos \u00a0instancias \u00abse \u00a0hayan salido de dicho enfoque de orientaci\u00f3n para condenar a \u00a0una persona sin valorar debidamente razones l\u00f3gicas de los \u00a0hechos que se les pone[n] \u00a0de \u00a0presente\u00bb. \u00a0<\/p>\n<p>A juicio del \u00a0letrado, la realidad procesal muestra que la condena est\u00e1 \u00a0ligada a dos hechos diferentes, \u00abdonde \u00a0la ubicabilidad del presunto actor es movible tanto para reconocerlo \u00a0como ejecutor del hecho, como para botar un objeto en la calle, como \u00a0para caminar r\u00e1pidamente ante la persecuci\u00f3n del agente \u00a0captor, y por \u00faltimo, que puede tomar trago o licor parado en \u00a0una esquina hasta cuando lo capturan\u00bb. \u00a0<\/p>\n<p>Entonces, los \u00a0juzgadores no aplicaron debidamente la sana cr\u00edtica, sino que \u00a0se apartaron de la verdad de los hechos \u00abque \u00a0al deprecar duda genera ausencia de responsabilidad\u00bb, \u00a0con lo cual se vulner\u00f3 el principio de presunci\u00f3n de \u00a0inocencia. \u00a0<\/p>\n<p>Otras pruebas, \u00a0como la incautaci\u00f3n del arma y el testimonio de un perito en \u00a0bal\u00edstica, \u00abno \u00a0son del todo contundentes para esgrimir el fallo atacado\u00bb, \u00a0porque el verdadero soporte de la condena es la prueba testimonial \u00a0antes referida. \u00a0<\/p>\n<p>Solicita se case \u00a0el fallo recurrido y, en su lugar, se absuelva a su defendido. \u00a0<\/p>\n<p>CONSIDERACIONES \u00a0<\/p>\n<p>1. La admisi\u00f3n \u00a0de una demanda de casaci\u00f3n, en el sistema acusatorio de la Ley \u00a0906 de 2004, est\u00e1 condicionada al cumplimiento de los \u00a0requisitos consagrados en el art\u00edculo 184, referidos a la \u00a0correcta selecci\u00f3n de la causal invocada, cuyo desarrollo debe \u00a0contener un m\u00ednimo de coherencia y precisi\u00f3n conceptual \u00a0que permita establecer, con facilidad, cu\u00e1l es el error que se \u00a0atribuye al sentenciador y su efecto determinante en la decisi\u00f3n \u00a0recurrida. \u00a0<\/p>\n<p>Es por ello que la \u00a0jurisprudencia de la Sala viene insistiendo que no se trata de un \u00a0mecanismo de libre configuraci\u00f3n, desprovisto de todo rigor, \u00a0sino que, por el contrario, dada su naturaleza extraordinaria, quien \u00a0acude al mismo debe ce\u00f1irse a determinados requerimientos \u00a0sistem\u00e1ticos basados en la raz\u00f3n y en la l\u00f3gica \u00a0argumentativa, atinentes a la observancia de coherencia, precisi\u00f3n \u00a0y claridad en el desarrollo de cada uno de los reparos efectuados, y \u00a0desarrollarlos conforme a las causales de procedencia previstas en el \u00a0aludido canon 181 del ordenamiento procesal, en aras de persuadir a \u00a0esta Corporaci\u00f3n de revisar el fallo de segunda instancia con \u00a0el fin de corregir el pronunciamiento que se revela contrario a \u00a0derecho. \u00a0<\/p>\n<p>Adem\u00e1s de \u00a0esos fundamentos, el impugnante tiene la carga de justificar la \u00a0necesidad de intervenci\u00f3n de la Corte, en aras de cumplir con \u00a0una de las finalidades del recurso, esto es, la \u00a0efectividad del derecho material, el respeto de las garant\u00edas \u00a0de los intervinientes, la reparaci\u00f3n de los agravios inferidos \u00a0a estos, y la unificaci\u00f3n de la jurisprudencia. \u00a0<\/p>\n<p>En \u00a0t\u00e9rminos generales, la admisibilidad del libelo est\u00e1 \u00a0supeditada a (i) \u00a0que \u00a0el demandante tenga inter\u00e9s, (ii) \u00a0se \u00a0demuestre el agravio a los derechos o garant\u00edas fundamentales, \u00a0(iii) \u00a0se \u00a0se\u00f1ale la causal de casaci\u00f3n que se invoca para \u00a0demostrar la ocurrencia del yerro, con sujeci\u00f3n a las reglas \u00a0que gobiernan la postulaci\u00f3n y desarrollo de los reproches, en \u00a0el \u00e1mbito del motivo seleccionado para el efecto y, (iv) \u00a0se \u00a0presente un completo fundamento argumentativo que evidencie la \u00a0necesidad de materializar alguna de las finalidades del recurso, en \u00a0los t\u00e9rminos del art\u00edculo 180 de la Ley 906 de 2004. \u00a0<\/p>\n<p>2. El defensor del \u00a0procesado se margin\u00f3 por completo de las reglas que rigen la \u00a0impugnaci\u00f3n extraordinaria, porque no comprob\u00f3 que el \u00a0asunto requiere alcanzar alguno de tales prop\u00f3sitos y tampoco \u00a0se ci\u00f1\u00f3 a los par\u00e1metros l\u00f3gicos, \u00a0argumentativos y de postulaci\u00f3n, atinentes a los motivos \u00a0invocados. \u00a0<\/p>\n<p>Bastante se ha \u00a0insistido que cuando se acude a la causal segunda \u00a0de casaci\u00f3n, para demandar el desconocimiento del debido \u00a0proceso por afectaci\u00f3n sustancial de su estructura o de la \u00a0garant\u00eda debida a cualquiera de las partes, es imperativo \u00a0atender a unos m\u00ednimos requisitos para su admisi\u00f3n. \u00a0<\/p>\n<p>Bajo ese \u00a0entendido, al casacionista le corresponde identificar el yerro \u00a0protuberante que presenta el fallo y evidenciar su ocurrencia a \u00a0trav\u00e9s de una argumentaci\u00f3n l\u00f3gica y explicativa \u00a0de las razones por las cuales no es posible mantener vigente su \u00a0estructura jur\u00eddica. \u00a0<\/p>\n<p>Para un completo y \u00a0suficiente planteamiento del cargo, adem\u00e1s de identificar el \u00a0motivo sobre el cual gira la irregularidad denunciada, as\u00ed \u00a0como la causal de nulidad que se configura, las normas que se exhiben \u00a0vulneradas y el momento procesal a partir del cual se debe invalidar \u00a0la actuaci\u00f3n, tambi\u00e9n debe atender a los principios que \u00a0gobiernan el instituto, haciendo ver que no hay otra manera de \u00a0superar el da\u00f1o o perjuicio causado por la incorrecci\u00f3n, \u00a0toda vez que el recurso no se puede fundamentar en simples hip\u00f3tesis. \u00a0<\/p>\n<p>3. \u00a0En el marco de una redacci\u00f3n bastante confusa, el actor \u00a0postula, en el primer \u00a0cargo, \u00a0el desconocimiento del debido proceso, pero los fundamentos que \u00a0ofrece no evidencian el acaecimiento de un tal desafuero, cuya \u00a0demostraci\u00f3n debe partir por identificar el acto irregular y \u00a0la manera como \u00e9ste afect\u00f3 la integridad de la \u00a0actuaci\u00f3n o vulner\u00f3 las garant\u00edas procesales. \u00a0<\/p>\n<p>Contrario \u00a0a esas directrices, el censor, en el intento de acreditar la \u00a0transgresi\u00f3n de dicha garant\u00eda fundamental, esgrime una \u00a0serie de argumentos desordenados que impiden entender, en \u00faltimas, \u00a0cu\u00e1l es la fuente del supuesto vicio que pretende hacer valer, \u00a0pues, inicialmente, afirma que la afectaci\u00f3n al debido proceso \u00a0obedece a la existencia de dilaciones injustificadas y que la \u00a0judicatura se tom\u00f3 un tiempo extremadamente largo para adoptar \u00a0\u00abla \u00a0decisi\u00f3n que ahora nos ocupa\u00bb. \u00a0<\/p>\n<p>Enseguida, \u00a0replica que el Juez Segundo Penal del Circuito ya hab\u00eda \u00a0\u00abdeterminado \u00a0unos t\u00e9rminos de preclusividad de la pr\u00e1ctica de \u00a0pruebas en el juicio oral\u00bb y \u00a0le hab\u00eda dado un plazo razonable a la Fiscal\u00eda para \u00a0recaudar el testimonio de Diego \u00a0Giovanny Forero Dom\u00ednguez, \u00a0quien solo apareci\u00f3 cinco (5) a\u00f1os despu\u00e9s de \u00a0ocurridos los hechos. \u00a0<\/p>\n<p>Y \u00a0luego, asegura que esa declaraci\u00f3n, que afect\u00f3 los \u00a0intereses del procesado, \u00abes \u00a0un acto procesal fundamental que cercena la inocencia del mismo, ya \u00a0que despu\u00e9s de tanto tiempo de no ser escuchado el testimonio, \u00a0ello dio a adoptar una posici\u00f3n de importancia al ser \u00a0condenado\u00bb. \u00a0<\/p>\n<p>Es \u00a0n\u00edtido que tales planteamientos no est\u00e1n dirigidos a \u00a0demostrar la transgresi\u00f3n anunciada, sino a disentir de la \u00a0decisi\u00f3n que, en su momento, profiri\u00f3 el Tribunal \u00a0Superior de Bogot\u00e1, consistente en decretar la nulidad parcial \u00a0de lo actuado y del testimonio de cargo que con ocasi\u00f3n de esa \u00a0orden se recaud\u00f3 en el juicio oral, con argumentos que \u00a0desconocen las verdaderas motivaciones de la colegiatura para \u00a0disponer la invalidez de lo actuado desde la sesi\u00f3n del juicio \u00a0oral del 17 de septiembre de 2014, concretamente, a partir del \u00a0momento en que se declar\u00f3 cerrada la etapa probatoria, con el \u00a0fin de que se reinstalara la diligencia y la Fiscal\u00eda pudiera \u00a0hacer comparecer a los testigos, Diego \u00a0Giovanny Forero Dom\u00ednguez y \u00a0Carlos \u00a0Qui\u00f1\u00f3nez Pinz\u00f3n. \u00a0<\/p>\n<p>Ello \u00a0es as\u00ed, porque no demuestra que en verdad se presentaron \u00a0dilaciones injustificadas y, l\u00f3gicamente, tampoco suministra \u00a0las razones por las cuales esa situaci\u00f3n habr\u00eda \u00a0afectado las garant\u00edas de su asistido, simplemente se queja de \u00a0que el Tribunal se tom\u00f3 un tiempo extremadamente largo para \u00a0adoptar el fallo de segundo grado, cuesti\u00f3n que por s\u00ed \u00a0sola no traduce una irregularidad sustancial que requiera ser \u00a0remediada. \u00a0<\/p>\n<p>Pretende \u00a0desconocer que la decisi\u00f3n del 8 de mayo de 2014, de \u00a0retrotraer lo actuado a la fase probatoria, se fundament\u00f3 en \u00a0la necesidad de sanear los defectos en que incurri\u00f3 el Juez \u00a0Segundo Penal del Circuito, en la sesi\u00f3n de juicio oral que \u00a0tuvo lugar el 17 de septiembre de 2014. \u00a0<\/p>\n<p>En \u00a0efecto, seg\u00fan puso de presente la colegiatura en esa ocasi\u00f3n, \u00a0que dicho funcionario hab\u00eda anunciado que en la pr\u00f3xima \u00a0oportunidad se\u00f1alada, esto es, el 17 de septiembre de 2014, \u00a0adelantar\u00eda el juicio oral hasta su culminaci\u00f3n, con \u00a0quienes comparecieran, y efectivamente as\u00ed ocurri\u00f3, \u00a0pues en la misma calenda dio por culminada la etapa probatoria, \u00a0escuch\u00f3 alegatos finales, anunci\u00f3 el sentido del fallo \u00a0y dict\u00f3 sentencia. \u00a0<\/p>\n<p>Proceder \u00a0con el cual desatendi\u00f3 la petici\u00f3n de la Fiscal\u00eda \u00a0de suspender la diligencia para que se intentara, a trav\u00e9s de \u00a0conducci\u00f3n, la comparecencia de dos testigos fundamentales \u00a0para su teor\u00eda del caso, bajo la creencia de que, en virtud \u00a0del principio de concentraci\u00f3n, las pruebas se deben practicar \u00a0en una sola sesi\u00f3n, cuando ninguna preceptiva as\u00ed lo \u00a0establece. \u00a0<\/p>\n<p>En \u00a0suma, concret\u00f3 as\u00ed, las imprecisiones de dicho \u00a0funcionario judicial: \u00a0<\/p>\n<p>i) \u00a0Confunde y toma por una misma cosa, sin serlo, dos aspectos \u00a0procesales distintos: i) la etapa de juzgamiento como tal y ii) la \u00a0audiencia del juicio oral donde se practican las pruebas. \u00a0<\/p>\n<p>Puede \u00a0ser cierto que en el presente asunto la fase de juzgamiento se ha \u00a0prolongado por diversos motivos. Pero no as\u00ed, que la audiencia \u00a0del juicio oral donde se practican las pruebas se haya extendido, al \u00a0punto de desvanecer el principio de concentraci\u00f3n. \u00a0<\/p>\n<p>ii) \u00a0La audiencia de juicio oral se program\u00f3 para el 13 de \u00a0noviembre de 2013, y s\u00f3lo se presentaron dos testigos de la \u00a0Fiscal\u00eda y nadie acudi\u00f3 por la defensa. Por ello, el \u00a0funcionario judicial prefiri\u00f3 no iniciar. \u00a0<\/p>\n<p>Lo \u00a0cierto es que la \u00fanica sesi\u00f3n donde se practicaron \u00a0\u201ctodas\u201d las pruebas fue la del 17 de septiembre de 2014: \u00a0la misma donde el Fiscal delegado pidi\u00f3 la suspensi\u00f3n \u00a0para que se hiciera comparecer, por conducci\u00f3n, a sus dos \u00a0testigos m\u00e1s importantes, que no acudieron. \u00a0<\/p>\n<p>iii) \u00a0As\u00ed las cosas, no compagina con la realidad sostener que, en \u00a0este asunto, la solicitud de la Fiscal\u00eda produjera un \u00a0irrazonable desconocimiento del principio de concentraci\u00f3n15. \u00a0<\/p>\n<p>M\u00e1s \u00a0adelante, se refiri\u00f3 as\u00ed al caso concreto: \u00a0<\/p>\n<p>En \u00a0el caso que se examina, el Fiscal 20 Seccional destac\u00f3 la \u00a0relevancia del aporte de los testigos que no comparecieron a la \u00a0audiencia de juicio oral. De una parte, Diego [G]iovanny \u00a0Forero Dom\u00ednguez, de quien dijo, es compa\u00f1ero de \u00a0trabajo de la v\u00edctima, presenci\u00f3 los hechos y aludir\u00e1 \u00a0a la participaci\u00f3n del implicado; y Carlos Qui\u00f1\u00f3nez \u00a0Pinz\u00f3n, agente de la Polic\u00eda Nacional, quien tom\u00f3 \u00a0las pruebas captadas en las manos del capturado en flagrancia, con el \u00a0fin de averiguar si registraban residuos de elementos compatibles con \u00a0disparos de arma de fuego. \u00a0<\/p>\n<p>A \u00a0pesar de que la negaci\u00f3n del Juez de suspender la diligencia, \u00a0para que se hiciera comparecer a los mencionados testigos, generaba \u00a0evidentes efectos sustanciales, el Juez de Conocimiento adopt\u00f3 \u00a0su decisi\u00f3n a trav\u00e9s de una orden, cuando lo adecuado \u00a0era la emisi\u00f3n de un auto (interlocutorio), lo notificara e \u00a0informara a los intervinientes los recursos procedentes contra la \u00a0decisi\u00f3n (art\u00edculo 162 numeral 7\u00ba C\u00f3digo de \u00a0Procedimiento Penal, Ley 906 de 2004). \u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>Por \u00a0manera que la orden impartida por el A quo elimin\u00f3 la \u00a0posibilidad de que el Fiscal delegado hubiese interpuesto el recurso \u00a0de apelaci\u00f3n, el cual procede \u201ccontra los autos \u00a0adoptados durante el desarrollo de las audiencias\u201d (art\u00edculo \u00a0176 ib\u00eddem). \u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>Por \u00a0\u00faltimo, cabe recordar que en su alegaci\u00f3n de cierre, el \u00a0Fiscal delegado plante\u00f3 la necesidad de invalidar parcialmente \u00a0lo actuado, debido a la postura reacia del Juez, cuando se neg\u00f3 \u00a0a suspender la audiencia de pruebas para no defraudar su propia \u00a0regla. Empero, en la sentencia de primera instancia se omiti\u00f3 \u00a0analizar esa postulaci\u00f3n. \u00a0<\/p>\n<p>Dicha \u00a0irregularidad es indicativa de una mala pr\u00e1ctica, pues por \u00a0mandato del art\u00edculo 162 (requisitos comunes de los autos y \u00a0sentencias) de la Ley 906 de 2004, cuando hubiere divisi\u00f3n de \u00a0criterios, la decisi\u00f3n debe contener \u201cla expresi\u00f3n \u00a0de los fundamentos de disenso\u201d16. \u00a0<\/p>\n<p>Esos \u00a0razonamientos, que el demandante pasa por alto, muestran que no se \u00a0trat\u00f3 de una dilaci\u00f3n injustificada, sino de la \u00a0necesidad de recomponer un tr\u00e1mite revestido de \u00a0irregularidades sustanciales, como corresponde a todo funcionario \u00a0judicial, en el marco de sus competencias, en garant\u00eda del \u00a0debido proceso y los derechos de las partes. \u00a0<\/p>\n<p>En tal sentido, la \u00a0actual petici\u00f3n de nulidad resulta abiertamente infundada, en \u00a0la medida que las r\u00e9plicas del demandante no conjugan con la \u00a0realidad procesal, al paso que se sirve de ella para afirmar, sin \u00a0argumento de peso, que la declaraci\u00f3n de Forero \u00a0Dom\u00ednguez \u00a0afect\u00f3 los intereses de su representado y, por consiguiente, \u00a0que se ha debido proferir un fallo con lo recaudado hasta el momento \u00a0en que el Juez Segundo Penal del Circuito clausur\u00f3 el debate \u00a0probatorio. \u00a0<\/p>\n<p>En sede del \u00a0recurso extraordinario, un ataque por nulidad no puede considerarse \u00a0como la oportunidad para plantear todas las inconformidades del \u00a0recurrente y someter el asunto a un nuevo estudio, m\u00e1xime \u00a0cuando lo que en verdad se busca, no es corregir la ilegalidad del \u00a0fallo cuestionado, sino obtener una soluci\u00f3n acorde a los \u00a0intereses defensivos. \u00a0<\/p>\n<p>Todo ello, bajo la \u00a0creencia, meramente subjetiva, que sus se\u00f1alamientos son \u00a0suficientes para derruir los cimientos del fallo de segunda \u00a0instancia, pues sin atender que la entremezcla de reparos atenta \u00a0contra el principio de autonom\u00eda, introduce a su pretensi\u00f3n \u00a0invalidante, argumentos que no se relacionan con la causal invocada, \u00a0sino con los yerros de apreciaci\u00f3n probatoria, como ocurre \u00a0cuando, adicionalmente, se queja de la credibilidad otorgada al \u00a0indicado testigo de cargo bajo la hip\u00f3tesis no demostrada, de \u00a0que su memoria de los hechos ha sido afectada y que la condena de \u00a0Cort\u00e9s \u00a0S\u00e1ez se \u00a0ciment\u00f3, \u00fanicamente, por la forma como estaba vestido y \u00a0no por sus rasgos f\u00edsicos. \u00a0<\/p>\n<p>La censura no \u00a0puede ser admitida. \u00a0<\/p>\n<p>4. En relaci\u00f3n \u00a0con el segundo \u00a0cargo (subsidiario), \u00a0tambi\u00e9n advierte la Sala insuperables deficiencias que impiden \u00a0su admisi\u00f3n. \u00a0<\/p>\n<p>Cuando se plantea \u00a0en casaci\u00f3n la ocurrencia de errores de hecho por falso \u00a0raciocinio, al interesado le compete demostrar que la valoraci\u00f3n \u00a0efectuada por el juzgador quebranta ostensiblemente los postulados \u00a0l\u00f3gicos, cient\u00edficos o emp\u00edricos y que, por ese \u00a0efecto, termina declarando una verdad distinta a la que muestra la \u00a0realidad procesal. Esa labor, implica confrontar las precisas \u00a0consideraciones del sentenciador, para hacer ver la ocurrencia del \u00a0desacierto, as\u00ed como su directa incidencia en la determinaci\u00f3n \u00a0adoptada, de tal forma que, en ausencia del mismo, lo resuelto \u00a0hubiese sido diametralmente opuesto y favorable a los intereses del \u00a0recurrente. \u00a0<\/p>\n<p>El alegato del \u00a0demandante no concreta alguna desatenci\u00f3n de las reglas de la \u00a0sana cr\u00edtica frente a la estimaci\u00f3n realizada en las \u00a0instancias, pues todos sus cuestionamientos traducen un desacuerdo \u00a0con la forma como se examin\u00f3 la prueba de cargo, pero en \u00a0ning\u00fan momento se detuvo a explicar ni a objetivar porqu\u00e9 \u00a0el criterio del juzgador el il\u00f3gico, absurdo o irrazonable. \u00a0<\/p>\n<p>Su prop\u00f3sito \u00a0es prolongar un debate debidamente zanjado en las instancias, toda \u00a0vez que el Tribunal despach\u00f3 en forma negativa la misma \u00a0propuesta, porque advirti\u00f3 que la contradicci\u00f3n \u00a0detectada por el defensor, es apenas una imprecisi\u00f3n que no \u00a0desdibuja las cuestionadas narraciones. \u00a0<\/p>\n<p>As\u00ed \u00a0discurri\u00f3: \u00a0<\/p>\n<p>El defensor \u00a0reprocha que Oscar Orlando Castro Ram\u00edrez, Patrullero de la \u00a0Polic\u00eda Nacional indic\u00f3 que al momento de capturar a la \u00a0persona que le se\u00f1al\u00f3 Diego Giovanny Forero Dom\u00ednguez \u00a0\u2013presencial- \u00a0tuvo \u00a0que perseguirlo porque aqu\u00e9l iba caminando a paso ligero, en \u00a0tanto que, Forero Dom\u00ednguez manifest\u00f3 que dicho sujeto \u00a0al tiempo de su aprehensi\u00f3n se encontraba de pie en la esquina \u00a0consumiendo licor, como si nada hubiese pasado. \u00a0<\/p>\n<p>La defensa \u00a0encuentra en esa diferencia una contradicci\u00f3n muy relevante, \u00a0suficiente para minar la credibilidad de los testigos \u2013Oscar \u00a0Orlando Castro Ram\u00edrez y Diego Giovanny Forero Dom\u00ednguez-. \u00a0Empero, \u00a0observado el asunto en sana cr\u00edtica, la Sala no llega a la \u00a0misma conclusi\u00f3n, pues se trata de una imprecisi\u00f3n que \u00a0en nada desdibuja lo narrado por el testigo presencial y el agente \u00a0captor. \u00a0<\/p>\n<p>Lo realmente \u00a0importante, es que Diego Giovanny Forero Dom\u00ednguez \u00a0\u2013presencial- \u00a0colabor\u00f3 \u00a0a los agentes de la Polic\u00eda Nacional para identificar a HAROLD \u00a0SMITH CORT\u00c9S S\u00c1EZ, a trav\u00e9s del se\u00f1alamiento \u00a0directo, el mismo d\u00eda de la comisi\u00f3n del delito, \u00a0identific\u00e1ndolo por sus prendas de vestir, actitud en la que \u00a0coincidi\u00f3, con Oscar Orlando Castro Ram\u00edrez \u2013agente \u00a0captor-, que tambi\u00e9n observ\u00f3 a CORT\u00c9S S\u00c1EZ \u00a0arrojar un elemento al piso, que luego de su verificaci\u00f3n \u00a0logr\u00f3 establecer que se trataba de un arma de fuego, situaci\u00f3n \u00a0que se corrobor\u00f3 adem\u00e1s con el testimonio de Harold \u00a0Augusto Mclean Villarraga \u2013perito qu\u00edmico- quien dio \u00a0cuenta que en las manos y prendas de vestir de CORT\u00c9S S\u00c1EZ \u00a0se encontraro[n] \u00a0residuos \u00a0de disparos. \u00a0<\/p>\n<p>De igual \u00a0manera, alega que Oscar Orlando Castro Ram\u00edrez, patrullero de \u00a0la Polic\u00eda Nacional, no especific\u00f3 con claridad si \u00a0CORT\u00c9S \u00a0S\u00c1EZ portaba \u00a0o no en sus manos el arma de fuego, sino que \u00fanicamente \u00a0manifest\u00f3 que percibi\u00f3 un lanzamiento de un presunto \u00a0objeto y no arma de fuego. \u00a0<\/p>\n<p>El anterior \u00a0argumento tampoco est\u00e1 llamado a prosperar, pues n\u00f3tese \u00a0que si bien el agente captor \u2013Oscar Orlando Castro Ram\u00edrez- \u00a0s\u00ed manifest\u00f3 que observ\u00f3 cuando el implicado \u00a0lanz\u00f3 un objeto, tambi\u00e9n lo es, que precis\u00f3 de \u00a0manera di\u00e1fana que una vez verific\u00f3 dicho elemento, \u00a0pudo constatar que se trataba de un arma de fuego, que luego de ser \u00a0sometida a an\u00e1lisis por parte del perito bal\u00edstico Luis \u00a0Eduardo L\u00f3pez G\u00f3mez \u2013escuchado en juicio- se \u00a0concluy\u00f3 que la misma era apta para disparar17. \u00a0<\/p>\n<p>N\u00f3tese que \u00a0el Tribunal, no desconoci\u00f3 la ambig\u00fcedad destacada por el \u00a0censor, sino que la apreci\u00f3 insuficiente para demeritar la \u00a0credibilidad de las narraciones suministradas por los cuestionados \u00a0deponentes, en la medida que coincidieron en lo sustancial, como \u00a0igualmente lo precis\u00f3 el fallador de primer grado: \u00a0<\/p>\n<p>En este punto, \u00a0se tiene que la defensa en su manifestaci\u00f3n final propuso que \u00a0se configuraban dudas en la estructuraci\u00f3n del injusto, dadas \u00a0las contradicciones en las que en su parecer incurrieron los \u00a0testigos, sin embargo, aunque en verdad pueden existir ciertas \u00a0disonancias e imprecisiones en los testimonios, aquellas no son \u00a0distorsiones que se presenten en aspecto esenciales o sustanciales, \u00a0pues la realidad es que confluyen en puntos relevantes que arrojan un \u00a0caudal suficiente como para derruir la presunci\u00f3n de inocencia \u00a0que cobija al enjuiciado18. \u00a0<\/p>\n<p>Bastante se ha \u00a0dicho19 \u00a0que la contradicci\u00f3n en que incurran dos personas no es \u00a0suficiente para restarle credibilidad y que al funcionario judicial \u00a0es a quien compete establecer, conforme a las reglas de la sana \u00a0cr\u00edtica, cu\u00e1les contenidos de las distintas \u00a0declaraciones merecen credibilidad. Es el desconocimiento de esos \u00a0par\u00e1metros de apreciaci\u00f3n, lo que habilita acudir a \u00a0esta sede, porque el hecho que el demandante no comparta el criterio \u00a0judicial, no traduce un yerro susceptible de ser cuestionado en esta \u00a0sede. \u00a0<\/p>\n<p>Como si fuera \u00a0poco, el actor se da a la tarea de proponer una alegaci\u00f3n \u00a0descontextualizada e indefinida, con la que solo pretende oponerse a \u00a0la verdad declarada en las instancias, procurando la absoluci\u00f3n \u00a0de su asistido por aplicaci\u00f3n del principio in \u00a0dubio pro reo \u00a0cuando ni siquiera se ocupa de demostrar el alegado desconocimiento \u00a0de los postulados de la sana cr\u00edtica, sino que se limit\u00f3 \u00a0a plantear una incertidumbre que no encuentra soporte en la \u00a0foliatura. \u00a0<\/p>\n<p>Importa recordar, \u00a0que la obligaci\u00f3n de resolver la duda a favor del procesado se \u00a0habilita cuando el universo probatorio v\u00e1lidamente incorporado \u00a0a la actuaci\u00f3n, no alcanza a despejar el estado de perplejidad \u00a0en que se soporta la pretensi\u00f3n absolutoria y, la consecuente \u00a0aspiraci\u00f3n de rescindir la declaraci\u00f3n de \u00a0responsabilidad, cuesti\u00f3n que el impugnante se margin\u00f3 \u00a0de acreditar. \u00a0<\/p>\n<p>No sobra insistir, \u00a0que la debida sustentaci\u00f3n de un cargo por falso raciocinio, \u00a0consiste en demostrar que el juez se alej\u00f3 de alg\u00fan \u00a0postulado cient\u00edfico, principio l\u00f3gico o m\u00e1xima \u00a0de la experiencia, y no, en \u00a0disentir de la estimaci\u00f3n judicial de los elementos de juicio, \u00a0como ocurre en este caso, donde el recurrente nuevamente \u00a0evade las verdaderas motivaciones que soportan el reproche penal, y \u00a0centra la atenci\u00f3n en asuntos apenas marginales, encaminados a \u00a0convencer que las contradicciones de los testigos son trascendentales \u00a0y que ellos son el verdadero soporte de la condena, porque las otras \u00a0pruebas, como la incautaci\u00f3n del arma y el testimonio de un \u00a0perito en bal\u00edstica, \u00abno \u00a0son del todo contundentes para esgrimir el fallo atacado\u00bb, \u00a0promoviendo as\u00ed un debate infundado, que escapa a la \u00f3rbita \u00a0del recurso de casaci\u00f3n. \u00a0<\/p>\n<p>As\u00ed las \u00a0cosas, el letrado redujo su discurso a enfrentar su personal \u00a0apreciaci\u00f3n probatoria con la del sentenciador, sin atender \u00a0que esta prevalece a la del sujeto procesal, porque est\u00e1 \u00a0amparada de la doble presunci\u00f3n de acierto y legalidad, en el \u00a0entendido que los hechos y las pruebas fueron correctamente valorados \u00a0y el derecho estrictamente aplicado y que esa presunci\u00f3n solo \u00a0se derrumba ante la demostraci\u00f3n clara de un vicio \u00a0trascendente, lo cual no se avizora en este caso. \u00a0<\/p>\n<p>5. \u00a0Se concluye, que los reproches del demandante no se afianzan en los \u00a0par\u00e1metros que rigen la casaci\u00f3n, porque no se trata de \u00a0un espacio al que se pueda acudir para presentar, de manera libre, \u00a0opiniones personales, con el anhelo de obtener una valoraci\u00f3n \u00a0alterna a la efectuada en las instancias. \u00a0<\/p>\n<p>En consecuencia, \u00a0se habr\u00e1 de inadmitir la demanda. \u00a0<\/p>\n<p>6. Contra esta \u00a0determinaci\u00f3n \u00a0procede el mecanismo de insistencia, de conformidad con lo \u00a0establecido en el art\u00edculo 184 de la Ley 906 de 2004, cuyas \u00a0reglas, en ausencia de disposici\u00f3n legal, han sido definidas \u00a0por la Corte desde el a\u00f1o 2005, en CSJ AP, 12 dic.2005, rad. \u00a024322 y precisadas en AP-3481-201420. \u00a0<\/p>\n<p>En m\u00e9rito \u00a0de lo expuesto, la Sala de Casaci\u00f3n Penal de la Corte Suprema \u00a0de Justicia, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>INADMITIR la \u00a0demanda formulada a nombre de Harold \u00a0Smith Cort\u00e9s S\u00e1ez. \u00a0<\/p>\n<p>Contra esta \u00a0decisi\u00f3n procede el mecanismo de insistencia, de conformidad \u00a0con el art\u00edculo 184, inciso 2\u00ba, del C\u00f3digo de \u00a0Procedimiento Penal. \u00a0<\/p>\n<p>Notif\u00edquese \u00a0y c\u00famplase \u00a0<\/p>\n<p>EYDER \u00a0PATI\u00d1O CABRERA \u00a0<\/p>\n<p>JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>JOS\u00c9 \u00a0LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>EUGENIO \u00a0FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>LUIS \u00a0ANTONIO HERN\u00c1NDEZ BARBOSA \u00a0<\/p>\n<p>PATRICIA \u00a0SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>LUIS \u00a0GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA \u00a0YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folio 16 Cuaderno del Tribunal. \u00a0<\/p>\n<p>2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folio 4 de la Carpeta 1. \u00a0<\/p>\n<p>3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 1 a 4 Ib. \u00a0<\/p>\n<p>4 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folio 20 Ib. \u00a0<\/p>\n<p>5 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 83 a 85 Ib. \u00a0<\/p>\n<p>6 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 127 a 132 Ib. \u00a0<\/p>\n<p>7 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 135 a 145 Ib. \u00a0<\/p>\n<p>8 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 177 a 211 Ib. \u00a0<\/p>\n<p>9 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folio 267 Ib. \u00a0<\/p>\n<p>10 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 268 y 278 Ib. \u00a0<\/p>\n<p>11 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folio 1 de la Carpeta 2. \u00a0<\/p>\n<p>12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Discerni\u00f3 el A quo que no pod\u00eda condenar por el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0delito de tentativa de homicidio, toda vez que la conducta \u00a0 \u00a0 \u00a0 \u00a0 \u00a0desarrollada por el procesado fue la de lesiones personales \u00a0 \u00a0 \u00a0 \u00a0 \u00a0culposas, pues al momento de realizar los disparos, ten\u00eda \u00a0 \u00a0 \u00a0 \u00a0 \u00a0como prop\u00f3sito definido lesionar a un desconocido, con el que \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sostuvo una ri\u00f1a, pero, por error en la ejecuci\u00f3n de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ese acto -aberratio ictus-, caus\u00f3 lesiones a un \u00a0 \u00a0 \u00a0 \u00a0 \u00a0recolector de basuras \u2013el aqu\u00ed ofendido- que en ese \u00a0 \u00a0 \u00a0 \u00a0 \u00a0momento y lugar se encontraba desempe\u00f1ando las funciones \u00a0 \u00a0 \u00a0 \u00a0 \u00a0propias de su cargo. \u00a0<\/p>\n<p>13 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 2 a 30 Ib. \u00a0<\/p>\n<p>14 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 15 a 43 Cuaderno del Tribunal. \u00a0<\/p>\n<p>15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folio 31 Carpeta 1. \u00a0<\/p>\n<p>16 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 39 a 42 Ib. \u00a0<\/p>\n<p>17 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folios 35 y 36 Cuaderno del Tribunal. \u00a0<\/p>\n<p>18 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Folio 9 Carpeta 2. \u00a0<\/p>\n<p>19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr, entre muchas otras, auto del 9 de octubre de 2013, radicado \u00a0 \u00a0 \u00a0 \u00a0 \u00a040768. \u00a0<\/p>\n<p>20 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Radicado 42597. \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 EYDER \u00a0PATI\u00d1O CABRERA \u00a0 Magistrado \u00a0Ponente \u00a0 AP671-2019 \u00a0 Radicaci\u00f3n \u00a0n\u00b0.52628 \u00a0 (Aprobado \u00a0acta n\u00b0. 52) \u00a0 Bogot\u00e1, \u00a0D.C., veintisiete (27) de febrero de dos mil diecinueve (2019). \u00a0 MOTIVO \u00a0DE LA DECISI\u00d3N \u00a0 Decide \u00a0la Sala si es procedente admitir la demanda de casaci\u00f3n \u00a0presentada por el defensor de Harold [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-43370","post","type-post","status-publish","format-standard","hentry","category-28"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/43370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=43370"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/43370\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=43370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=43370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=43370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}