{"id":36473,"date":"2023-09-13T21:42:03","date_gmt":"2023-09-13T21:42:03","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap787-201851609\/"},"modified":"2023-09-13T21:42:03","modified_gmt":"2023-09-13T21:42:03","slug":"ap787-201851609","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap787-201851609\/","title":{"rendered":"AP787-2018(51609)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>FERNANDO ALBERTO CASTRO \u00a0CABALLERO \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>AP787-2018 \u00a0<\/p>\n<p>Radicaci\u00f3n: 51609 \u00a0<\/p>\n<p>Aprobado Acta N. 065 \u00a0<\/p>\n<p>Bogot\u00e1, D. C., \u00a0veintiocho (28) de febrero de dos mil dieciocho (2018). \u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Procede \u00a0la Sala a estudiar los requisitos de adecuada fundamentaci\u00f3n \u00a0de la demanda de casaci\u00f3n promovida por la defensa de Jadirk \u00a0Raad Herrera, contra el \u00a0fallo de 17 de julio de 2017, emitido por el Tribunal Superior de \u00a0Bucaramanga, confirmatorio de la sentencia proferida por el Juzgado 3 \u00a0Penal del Circuito de Barrancabermeja que lo conden\u00f3 como \u00a0autor del delito de demanda de explotaci\u00f3n sexual comercial de \u00a0persona menor de 18 a\u00f1os de edad. \u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>Fueron \u00a0consignados en la sentencia as\u00ed: \u00a0<\/p>\n<p>En el mes de julio de 2010 \u00a0la ni\u00f1a Lesly Johana Vesga de 16 a\u00f1os de edad, fue \u00a0invitada por su primo ANDRES GABRIEL CASTRO GALVAN alias Monchi a \u00a0almorzar en el corregimiento del centro de Barrancabermeja, yendo en \u00a0compa\u00f1\u00eda de Lesly Johana para que tuvieran relaciones \u00a0sexuales con JADIRK por la suma de cien mil pesos. \u00a0<\/p>\n<p>Durante los siguientes d\u00edas \u00a0la menor recibi\u00f3 llamadas de hombres que la invitaban a salir \u00a0por dinero, siendo informada por el mismo Andr\u00e9s Gabriel que \u00a0hab\u00eda dado su n\u00famero de celular, ya que por cada n\u00famero \u00a0que diera de una ni\u00f1a recib\u00eda la suma de veinte mil \u00a0pesos. \u00a0<\/p>\n<p>La ni\u00f1a Valentina \u00a0Vega Aislant [de 13 \u00a0a\u00f1os de edad] \u00a0a comienzos del mes de octubre de 2010, sali\u00f3 de la casa en \u00a0compa\u00f1\u00eda de Andr\u00e9s Gabriel Castro Galv\u00e1n \u00a0con el fin de comprar unas bolsas, lo cual aprovech\u00f3 Andr\u00e9s \u00a0Gabriel para llevarla en su motocicleta por la carrilera, hasta un \u00a0sitio solitario y oscuro donde procedi\u00f3 a manosearla en su \u00a0cuerpo e hizo que le succionara el pene y para acallarla la amenaz\u00f3 \u00a0que pod\u00eda hacerle da\u00f1o a ella y a la mam\u00e1; \u00a0durante los siguientes d\u00edas le hac\u00edan llamadas para que \u00a0saliera con amigos por plata que saliera con JADIRK que \u00e9l \u00a0le \u00a0pagaba bien, que se acostara con \u00e9l y le daba plata, que eso \u00a0lo hac\u00eda su hermana Lesly que se acostaba con hombres por \u00a0plata y que le dijera a su prima Mar\u00eda Isabel que tiene 17 \u00a0a\u00f1os, que saliera con hombres por plata. \u00a0<\/p>\n<p>ACTUACION PROCESAL \u00a0<\/p>\n<p>1. Los hechos fueron \u00a0denunciados por la madre de una de las menores, lo cual dio lugar a \u00a0que en audiencia de 27 de abril de 2011 se formulara imputaci\u00f3n \u00a0a Jadirk Raad Herrera y \u00a0Andr\u00e9s Gabriel \u00a0Castro Galv\u00e1n como \u00a0autor, el primero, del delito de demanda de explotaci\u00f3n sexual \u00a0comercial de persona menor de 18 a\u00f1os y, el segundo, de los \u00a0punibles de acceso carnal abusivo con menor de 14 a\u00f1os y \u00a0proxenetismo, cargos que ambos rechazaron. \u00a0<\/p>\n<p>Los dos procesados fueron \u00a0cobijados con medida de aseguramiento privativa de libertad en centro \u00a0de reclusi\u00f3n. \u00a0<\/p>\n<p>2. El escrito de acusaci\u00f3n \u00a0fue presentado el 23 de mayo de ese a\u00f1o y fue formulado en \u00a0diligencia de junio 14 ante la Juez 3\u00ba Penal del Circuito de la \u00a0ciudad de Barrancabermeja. \u00a0<\/p>\n<p>3. La audiencia preparatoria \u00a0concluy\u00f3 el 13 de junio de 2012, debido a los m\u00faltiples \u00a0aplazamientos solicitados por la defensa y por el recurso de \u00a0apelaci\u00f3n que interpuso esta parte contra una decisi\u00f3n \u00a0que neg\u00f3 un pedido anulatorio. \u00a0<\/p>\n<p>4. La audiencia de juicio oral \u00a0culmin\u00f3 el 28 de noviembre de 2014, momento en el que se \u00a0anunci\u00f3 que el fallo ser\u00eda condenatorio para los dos \u00a0acusados. \u00a0<\/p>\n<p>5. En la audiencia que estaba \u00a0prevista para la lectura de la sentencia -10 \u00a0de abril de 2015-, \u00a0la juez invalid\u00f3 el sentido del fallo al considerar que deb\u00eda \u00a0ser absolutorio para Jadirk \u00a0Raad por atipicidad de \u00a0la conducta, \u00a0como no respecto de Andr\u00e9s \u00a0Gabriel Castro. \u00a0<\/p>\n<p>Como consecuencia de esa \u00a0decisi\u00f3n se dispuso la liberaci\u00f3n inmediata del \u00a0procesado absuelto. \u00a0<\/p>\n<p>6. La Fiscal\u00eda interpuso \u00a0recurso de apelaci\u00f3n, el cual fue resuelto por el Tribunal \u00a0Superior de Bucaramanga en auto de 22 de julio de 2016, en el que \u00a0revoc\u00f3 la decisi\u00f3n del juez de primer grado, \u00a0orden\u00e1ndole que emitiera el fallo de conformidad con el \u00a0sentido anunciado desde un inicio en la audiencia del 28 de noviembre \u00a0de 2014. \u00a0<\/p>\n<p>7. Es as\u00ed que la \u00a0sentencia de primer grado se profiri\u00f3 el 4 de noviembre de \u00a02016, en la que se impuso a Jadirk \u00a0Raad Herrera la pena de \u00a0190 meses de prisi\u00f3n como autor del delito de demanda de \u00a0explotaci\u00f3n sexual comercial con persona menor de 18 a\u00f1os, \u00a0y a Andr\u00e9s \u00a0Gabriel Castro, la \u00a0sanci\u00f3n de 280 meses de prisi\u00f3n como autor de los \u00a0delitos de acceso carnal abusivo con menor de 14 a\u00f1os agravado \u00a0y proxenetismo. \u00a0<\/p>\n<p>Se neg\u00f3 la suspensi\u00f3n \u00a0condicional de la ejecuci\u00f3n de la pena y la prisi\u00f3n \u00a0domiciliaria, raz\u00f3n por la que se dispuso que Andr\u00e9s \u00a0Gabriel Castro Galv\u00e1n continuara \u00a0privado de libertad cumpliendo la pena, mientras que frente a \u00a0Jadirk Raad Herrera se \u00a0libr\u00f3 orden de captura. \u00a0<\/p>\n<p>8. La sentencia de primer grado \u00a0fue apelada por los defensores de los acusados. El Tribunal de \u00a0Bucaramanga se pronunci\u00f3 en fallo de 17 de julio de 2017, \u00a0confirmando en su integridad la decisi\u00f3n de primer grado. \u00a0<\/p>\n<p>9. Recurre en casaci\u00f3n \u00a0la defensa de Jadirk \u00a0Raad Herrera. \u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>Una vez resume los hechos, la \u00a0actuaci\u00f3n procesal y las sentencias de primera y segunda \u00a0instancia, el recurrente anuncia que se ocupar\u00e1 del an\u00e1lisis \u00a0de la tipicidad de la conducta enrostrada al procesado, la cual se \u00a0describen en el art\u00edculo 217 A del estatuto represor. \u00a0<\/p>\n<p>1. Para ello acude a la causal \u00a0primera de casaci\u00f3n, alegando la interpretaci\u00f3n err\u00f3nea \u00a0de la norma que tipifica el delito de demanda de explotaci\u00f3n \u00a0sexual comercial de persona menor de 18 a\u00f1os de edad. \u00a0<\/p>\n<p>Como normas violadas identifica \u00a0los art\u00edculos 9, 10 y 217 A del C\u00f3digo Penal. \u00a0<\/p>\n<p>En sustento de su queja, el \u00a0censor cita apartes de la exposici\u00f3n de motivos y los \u00a0antecedentes de la ley 1329 de 2009, introductoria al orden jur\u00eddico \u00a0nacional del tipo penal en cuesti\u00f3n, frente a los cuales \u00a0despliega su propio an\u00e1lisis para sostener que el prop\u00f3sito \u00a0de este tipo penal es el de castigar la conducta del cliente, \u00a0explotador o abusador, por ser \u00e9ste quien genera y sostiene la \u00a0problem\u00e1tica, situaci\u00f3n que en su criterio dista del \u00a0comportamiento que se reprocha a su defendido, el cual se limit\u00f3 \u00a0a ofrecer una d\u00e1diva a una menor de 18 a\u00f1os a cambio de \u00a0favores sexuales. \u00a0<\/p>\n<p>Para el censor la conducta \u00a0descrita en el art\u00edculo 217 A se encamina a contrarrestar \u00a0fen\u00f3menos como el turismo sexual con menores de edad, m\u00e1s \u00a0no el comportamiento de algunos ciudadanos que act\u00faan por \u00a0fuera de todo ese engranaje comercial y deciden ofrecer dinero a \u00a0menores de 18 a\u00f1os en contraprestaci\u00f3n de servicios \u00a0sexuales, conducta que para el demandante resulta at\u00edpica. \u00a0<\/p>\n<p>De otro lado, alude a que no se \u00a0demostr\u00f3 el dolo en el actuar de Raad \u00a0Herrera, aspecto que, \u00a0a\u00f1ade, no se pod\u00eda sustraer del an\u00e1lisis del \u00a0fallador aun cuando se le enrostre un delito de mera conducta, en \u00a0tanto se requieren dar por satisfechos los elementos tanto de la \u00a0tipicidad objetiva como subjetiva. \u00a0<\/p>\n<p>Vuelve a la exposici\u00f3n \u00a0de motivos de la ley que tipific\u00f3 la conducta en cuesti\u00f3n \u00a0al se\u00f1alar que en manera alguna se sanciona a la persona que \u00a0de manera ocasional ofrece dinero, un dulce o una d\u00e1diva a un \u00a0menor de edad para sostener un encuentro sexual con \u00e9ste, \u00a0habida cuenta que en su criterio, se requiere de una conducta \u00a0habitual dentro de todo un emporio comercial, circunstancias que no \u00a0corresponden a este caso. \u00a0<\/p>\n<p>En palabras del demandante: \u00ablo \u00a0que el delito busca sancionar es la utilizaci\u00f3n habitual de \u00a0los menores de edad por parte de organizaciones que permitan la \u00a0pr\u00e1ctica sexual y al cliente que a trav\u00e9s de las mismas \u00a0solicite o demande alguna acci\u00f3n, acto o servicio sexual de \u00a0menores de edad\u00bb. \u00a0<\/p>\n<p>Como argumento adicional indica \u00a0que la pena prevista para el delito descrito en el art\u00edculo \u00a0217 A, no se acompasa con la simple acci\u00f3n de una persona que \u00a0solicita a un menor de edad un servicio sexual que va a ser \u00a0remunerado, pues tal comportamiento no puede equipararse al del \u00a0cliente que en forma regular hace ese tipo de requerimiento a \u00a0empresas que se dedican a facilitar ese servicio, motivo por el que, \u00a0concluye, la acci\u00f3n de Raad \u00a0Herrera es at\u00edpica. \u00a0<\/p>\n<p>Precisa el recurrente que la \u00a0expresi\u00f3n \u00abcomercial\u00bb \u00a0que contiene la \u00a0descripci\u00f3n t\u00edpica, debe entenderse como un ingrediente \u00a0normativo del tipo, el cual no se verifica en este asunto. \u00a0<\/p>\n<p>Solicita que se case la \u00a0sentencia para que se emita fallo de reemplazo en el que se absuelva \u00a0a Jadirk Raad Herrera. \u00a0<\/p>\n<p>2. Como \u00a0segunda censura, invoca el censor la causal segunda con el prop\u00f3sito \u00a0de que se declare la nulidad del tr\u00e1mite por trasgresi\u00f3n \u00a0del debido proceso. \u00a0<\/p>\n<p>Agrega que se trasgredieron los \u00a0principios consagrados en los art\u00edculos 29 y 250 de la \u00a0Constituci\u00f3n, as\u00ed como el art\u00edculo 178 del \u00a0C\u00f3digo Penal (sic) \u00aben \u00a0cuanto a la forma de notificaci\u00f3n de los autos en las \u00a0respectivas audiencias\u00bb. \u00a0<\/p>\n<p>Plantea que la juez de primer \u00a0grado no pod\u00eda emitir el fallo condenatorio contra el acusado \u00a0en los t\u00e9rminos en los que se lo orden\u00f3 el Tribunal \u00a0Superior de Bucaramanga, pues al haber anulado el sentido de fallo \u00a0inicial para reconocer su equivocaci\u00f3n en torno a la \u00a0declaratoria de responsabilidad penal de Raad \u00a0Herrera y concluir que \u00a0en realidad su conducta era at\u00edpica, no pod\u00eda ahora \u00a0verse compelida a proferir una sentencia en contrav\u00eda de su \u00a0convencimiento sobre el caso. Por ello, sostiene el censor, ten\u00eda \u00a0que declararse impedida para que otro juez emitiera el fallo. \u00a0<\/p>\n<p>La nulidad la concreta en el \u00a0hecho de que la juez de primer grado no debi\u00f3 haber concedido \u00a0el recurso de apelaci\u00f3n contra su decisi\u00f3n de anular el \u00a0sentido del fallo que hab\u00eda sido condenatorio para ambos \u00a0procesados, mucho menos otorgarle plazo a la Fiscal\u00eda para que \u00a0sustentara la alzada. \u00a0<\/p>\n<p>Otra de las inconformidades que \u00a0pone de presente a modo de interrogante es \u00bfsi el juez de \u00a0segunda instancia puede conocer del recurso de apelaci\u00f3n de la \u00a0sentencia, aun cuando ya se ha pronunciado sobre el caso? \u00a0<\/p>\n<p>Lo anterior habida cuenta que \u00a0el mismo magistrado que en auto de 10 de abril de 2015 orden\u00f3 \u00a0a la juez de primer grado que emitiera fallo condenatorio, conoci\u00f3 \u00a0de la apelaci\u00f3n contra la sentencia proferida en esos \u00a0t\u00e9rminos. Para el recurrente este funcionario ten\u00eda que \u00a0declararse impedido en la medida en que ya hab\u00eda emitido \u00a0concepto sobre la responsabilidad penal del procesado. \u00a0<\/p>\n<p>Afirma que el acusado no ha \u00a0contado con la garant\u00eda de imparcialidad para que la sentencia \u00a0en su contra sea revisada con objetividad. \u00a0<\/p>\n<p>La petici\u00f3n frente a \u00a0este cargo es que se decrete la nulidad del tr\u00e1mite. \u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>1. \u00a0Resulta pertinente recordar que la casaci\u00f3n no es instancia \u00a0adicional a las ordinarias del tr\u00e1mite y por lo mismo, no ha \u00a0sido concebida como un instrumento que permita la continuaci\u00f3n \u00a0del debate f\u00e1ctico y jur\u00eddico llevado a cabo en un \u00a0proceso ya culminado, sino que por su propia naturaleza corresponde a \u00a0una sede \u00fanica que parte del supuesto de la terminaci\u00f3n \u00a0del juicio con el proferimiento de la sentencia de segunda instancia, \u00a0que se presume no solo acertada, sino tambi\u00e9n acorde en un \u00a0todo con el ordenamiento jur\u00eddico. \u00a0<\/p>\n<p>Es por lo \u00a0anterior que el quiebre de dicha presunci\u00f3n compete al \u00a0demandante a trav\u00e9s de la acreditaci\u00f3n de cualquiera de \u00a0las hip\u00f3tesis que taxativamente ha fijado el legislador como \u00a0causales para resquebrajar la sentencia, cada una de las cuales \u00a0impone una serie de requerimientos argumentativos que el recurrente \u00a0est\u00e1 en deber de cumplir. \u00a0<\/p>\n<p>2. El recurrente propone dos \u00a0cargos contra el fallo del Tribunal Superior de Bucaramanga, uno por \u00a0violaci\u00f3n directa y otro por desconocimiento del debido \u00a0proceso. \u00a0<\/p>\n<p>2.1 El primero de los reparos \u00a0encuentra consagraci\u00f3n en el numeral 1\u00ba del art\u00edculo \u00a0181 de la Ley 906 de 2004 y se relaciona \u00a0con el proceso de adecuaci\u00f3n normativa al supuesto de hecho \u00a0acogido por el fallador y que no puede ser objeto de discusi\u00f3n. \u00a0<\/p>\n<p>En esa medida, \u00a0para recurrir en casaci\u00f3n a trav\u00e9s de la causal \u00a0primera, (art. 181 de la Ley 906 de 2004), se exige al actor afirmar \u00a0y probar que el juzgador de segunda instancia ha incurrido en error \u00a0ya sea por: (i) falta de aplicaci\u00f3n o exclusi\u00f3n \u00a0evidente, que se presenta cuando el funcionario judicial yerra acerca \u00a0de la existencia de la norma y por eso no la aplica al caso \u00a0espec\u00edfico que la reclama, o ignora la ley que regula la \u00a0materia y por eso no la tiene en cuenta habiendo incurrido en error \u00a0sobre su existencia o validez en el tiempo o en el espacio; (ii) \u00a0aplicaci\u00f3n indebida, la cual se origina cuando el juzgador se \u00a0equivoca al calificar jur\u00eddicamente los hechos o, cuando \u00a0habiendo acertado en su adecuaci\u00f3n, falla al elegir la norma \u00a0correspondiente a la calificaci\u00f3n jur\u00eddica impartida; y \u00a0(iii) por interpretaci\u00f3n err\u00f3nea, que ocurre cuando el \u00a0juez selecciona adecuadamente la norma que corresponde al caso \u00a0sometido a su consideraci\u00f3n, pero se equivoca al \u00a0interpretarla, puesto que le atribuye un sentido jur\u00eddico que \u00a0no tiene o le asigna efectos contrarios a su real contenido. \u00a0<\/p>\n<p>El demandante sostiene que el \u00a0Tribunal hizo una incorrecta interpretaci\u00f3n del tipo penal \u00a0descrito en el art\u00edculo 217 A del C\u00f3digo Penal, \u00a0denominado Demanda de \u00a0explotaci\u00f3n sexual comercial de persona menor de 18 a\u00f1os \u00a0de edad, en la \u00a0medida en que este comportamiento solo se predica de la persona que \u00a0en su condici\u00f3n de cliente solicita los servicios sexuales de \u00a0menores de edad, a quien ejerce esa actividad comercial a modo de una \u00a0empresa. \u00a0<\/p>\n<p>Tal planteamiento evidencia \u00a0que el recurrente desconoce los hechos declarados en la sentencia, ya \u00a0que pasa por alto circunstancias relevantes del acontecer f\u00e1ctico, \u00a0las cuales no se remontan simplemente a la propuesta que hizo el \u00a0acusado a una menor de edad para que sostuviera relaciones sexuales \u00a0con \u00e9l a cambio de dinero, sino al pedido que \u00e9ste le \u00a0hizo a su compa\u00f1ero de causa Andr\u00e9s Gabriel Castro \u00a0Galv\u00e1n, con el fin de que lo contactara con menores para tal \u00a0cometido. \u00a0<\/p>\n<p>As\u00ed aconteci\u00f3 \u00a0con la menor L.J.V.A -de16 \u00a0a\u00f1os de edad para la \u00e9poca-, \u00a0prima de Castro Galv\u00e1n, la cual fue relacionada con Jadirk \u00a0Raad Herrera por \u00a0conducto de su familiar, quien adem\u00e1s le manifest\u00f3 el \u00a0inter\u00e9s de Raad \u00a0Herrera en sostener \u00a0relaciones sexuales con ella por lo que se le pagar\u00edan cien \u00a0mil pesos, dinero que la joven recibi\u00f3 luego del encuentro con \u00a0aquel. El mismo proceder se ejecut\u00f3 respecto de la menor \u00a0V.A.G, amiga de L.J.V.A. con la que Raad \u00a0Herrera tambi\u00e9n \u00a0sostuvo relaciones sexuales -ese \u00a0mismo d\u00eda y en el mismo lugar- \u00a0luego de que estuvo con L.J.V.A, a la que igualmente le pag\u00f3 \u00a0por sus servicios, gracias a que fue Andr\u00e9s Castro Galv\u00e1n \u00a0la persona que lo contact\u00f3 con ambas menores y fij\u00f3 con \u00a0\u00e9stas los pormenores de la d\u00e1diva que pag\u00f3 el \u00a0acusado. \u00a0<\/p>\n<p>Ninguna de las anteriores \u00a0particularidades fue puesta de presente por el recurrente, quien \u00a0modifica los hechos a su acomodo y concreta la conducta del procesado \u00a0a una mera propuesta sexual a una menor de edad por la que recibir\u00eda \u00a0una suma de dinero; para el demandante este no es un acto propio del \u00a0contexto comercial al que alude el tipo penal. \u00a0<\/p>\n<p>Es claro que infringe los \u00a0presupuestos de la violaci\u00f3n directa de la norma sustancial, \u00a0al re\u00f1ir con la declaraci\u00f3n de los hechos acogida en la \u00a0sentencia, puesto que de haber sido fiel a la misma, con toda \u00a0claridad habr\u00eda surgido que el acontecer enrostrado al \u00a0procesado Raad Herrera, \u00a0s\u00ed corresponde a la demanda de servicios sexuales con menores \u00a0de 18 a\u00f1os de edad en un contexto comercial, ya que acudi\u00f3 \u00a0a Andr\u00e9s Gabriel Castro Galv\u00e1n, persona que ejerc\u00eda \u00a0la actividad econ\u00f3mica de contactar a las adolescentes con los \u00a0hombres que requer\u00edan sus servicios sexuales. \u00a0<\/p>\n<p>De all\u00ed que la \u00a0hip\u00f3tesis f\u00e1ctica con la que el censor pretende \u00a0sustentar la violaci\u00f3n directa de la ley, no corresponda con \u00a0la situaci\u00f3n que se dio por probada en la sentencia. \u00a0<\/p>\n<p>Si su intenci\u00f3n era la \u00a0demostrar un error de derecho en la aplicaci\u00f3n de la norma a \u00a0la que se ajustaron lo hechos, el censor tuvo que haber abordado los \u00a0motivos por los que el Tribunal reafirm\u00f3 que tipicidad de la \u00a0conducta corresponde a la descripci\u00f3n del art\u00edculo 217 \u00a0A del C\u00f3digo Penal, los cuales consistieron en acoger la \u00a0interpretaci\u00f3n que de este tipo penal ya hizo la Corte, en el \u00a0sentido de que, en palabras del fallador de segundo grado, tal \u00a0conducta punible se actualiza, sin m\u00e1s ingredientes, cuando el \u00a0sujeto activo, por s\u00ed o por interpuesta persona, solicita o \u00a0demanda la prestaci\u00f3n de servicios sexuales, por parte de una \u00a0persona menor de 18 a\u00f1os, bajo promesa remuneratorio de \u00a0cualquier especie. \u00a0<\/p>\n<p>Pese al esfuerzo que hace el \u00a0demandante con base en su particular presentaci\u00f3n de los \u00a0hechos, que aun si los del fallo coincidieran con su postura, no \u00a0logra rebatir las razones por las que el supuesto f\u00e1ctico que \u00a0presenta, ha sido calificado por la jurisprudencia como t\u00edpico \u00a0del delito previsto en el art\u00edculo 217 A, habida cuenta que \u00a0deja de aportar argumentos nuevos de los ya considerados por la Sala \u00a0para concluir que el ofrecimiento que directamente se hace a un menor \u00a0de 18 a\u00f1os para que preste un favor sexual a cambio de \u00a0cualquier d\u00e1diva, comporta el delito de demanda comercial de \u00a0servicios sexuales con persona menor de 18 a\u00f1os. \u00a0<\/p>\n<p>Sobre el particular as\u00ed \u00a0se pronunci\u00f3 la Sala en CSJ SP 27 Sep. 2017, rad. 47862, \u00a0decisi\u00f3n en la que se cit\u00f3 como precedente el auto CSJ \u00a0AP, 4 Jun. 2013, rad. 40867: \u00a0<\/p>\n<p>De esta forma, \u00a0es palmario que la descripci\u00f3n t\u00edpica no prev\u00e9 \u00a0para su configuraci\u00f3n la necesidad de una red dedicada a la \u00a0prostituci\u00f3n infantil en la cual surja la promesa retributiva, \u00a0siendo suficiente la solicitud o demanda de servicios sexuales, es \u00a0decir, la conducta se agota con la sola propuesta, de suerte que no \u00a0es relevante si la persona accede a ella o no (CSJ AP 2172-2015). Por \u00a0ende, la expresi\u00f3n \u00abcomercial\u00bb as\u00ed sea \u00a0entendida como un ingrediente normativo del tipo, no se restringe a \u00a0las actividades de conglomerados mercantiles, al comprender tambi\u00e9n \u00a0actos propios de la vida cotidiana (\u2026) \u00a0<\/p>\n<p>En \u00a0consecuencia, desde esta arista, la postulaci\u00f3n del libelista \u00a0no cuenta con asidero, pues, se insiste, el il\u00edcito no exige \u00a0calidades especiales en el sujeto activo de la conducta, verbi \u00a0gratia, que se trate de un cliente usual de este tipo de actividades, \u00a0ni la concurrencia de elementos f\u00e1cticos adicionales. \u00a0<\/p>\n<p>Lo \u00a0expuesto hace palpable la incorrecta argumentaci\u00f3n del cargo \u00a0de violaci\u00f3n directa de la norma sustancial, pues por un lado, \u00a0soporta el presunto vicio en una realidad f\u00e1ctica diferente a \u00a0la declarada en la sentencia y, segundo, ning\u00fan error \u00a0identifica en la interpretaci\u00f3n del tipo penal por parte del \u00a0Tribunal, la cual se bas\u00f3 en el entendimiento que del mismo ya \u00a0fij\u00f3 la jurisprudencia de la Sala. \u00a0<\/p>\n<p>2.2 En el segundo reparo se \u00a0intenta por la senda de la causal segunda por desconocimiento del \u00a0debido proceso, concretamente del principio de imparcialidad. \u00a0<\/p>\n<p>En orden a verificar si se \u00a0satisfacen las puntuales exigencias del cargo de nulidad, pertinente \u00a0resulta fijar los antecedentes procesales que en criterio del censor \u00a0dan lugar a la invalidaci\u00f3n de lo actuado. \u00a0<\/p>\n<p>Se tiene que el juicio fue \u00a0adelantado por el Juzgado Tercero Penal del Circuito de \u00a0Barrancabermeja-Santander en cabeza de la juez Ana Mar\u00eda del \u00a0Kairo Jim\u00e9nez, funcionaria que en audiencia de 28 de noviembre \u00a0de 2014 emiti\u00f3 sentido de fallo, anunciando que ser\u00eda \u00a0condenatorio para ambos procesados por los cargos atribuidos en la \u00a0acusaci\u00f3n, al tiempo que fij\u00f3 como fecha para la \u00a0lectura de la sentencia el 19 de diciembre siguiente. \u00a0<\/p>\n<p>Finalmente, dicha actuaci\u00f3n \u00a0se posterg\u00f3 para el 10 de abril de 2015, fecha en la cual la \u00a0misma juez decidi\u00f3 \u00abnulitar \u00a0parcialmente el sentido del fallo que se emiti\u00f3 el 28 de \u00a0noviembre de 2014, el cual fue de car\u00e1cter condenatorio en \u00a0contra del se\u00f1or Jadirk \u00a0Raad y que en \u00a0esta oportunidad ser\u00e1 de naturaleza absolutoria por no \u00a0configurarse en su esplendor en lo atinente a la tipicidad de la \u00a0conducta de demanda de explotaci\u00f3n sexual comercial de persona \u00a0menor de 18 a\u00f1os y en su defecto se procede a erigir el \u00a0sentido del fallo de car\u00e1cter absolutorio a favor de Jadirk \u00a0Raad Herrera\u00bb \u00a0<\/p>\n<p>En esa audiencia la Fiscal\u00eda \u00a0interpuso recurso de apelaci\u00f3n para cuya sustentaci\u00f3n \u00a0solicit\u00f3 un plazo que fue concedido y fijado en tres d\u00edas. \u00a0El recurso se sustent\u00f3 el 13 de abril de 2015 y el Tribunal lo \u00a0resolvi\u00f3 el 22 de julio de 2016, revocando la decisi\u00f3n \u00a0del juez de primer grado para ordenarle que emitiera la sentencia de \u00a0acuerdo con el sentido anunciado el 28 de noviembre de 2014, toda vez \u00a0que esta actuaci\u00f3n es vinculante para el juez, quien no puede \u00a0modificarlo. Como sustento de esa decisi\u00f3n el Tribunal cit\u00f3 \u00a0varios pronunciamientos de la Corte sobre el tema. \u00a0<\/p>\n<p>As\u00ed las cosas la Juez \u00a0Tercera Penal del Circuito de Barrancabermeja, Dra. Ana Mar\u00eda \u00a0del Kairo Jim\u00e9nez, emiti\u00f3 sentencia de primer grado en \u00a0congruencia con lo anunciado en audiencia de 28 de noviembre de 2014. \u00a0<\/p>\n<p>Con motivo de la impugnaci\u00f3n \u00a0promovida por la defensa, la misma Sala que recov\u00f3 la \u00a0anulaci\u00f3n del sentido de fallo, se pronunci\u00f3, \u00a0confirmando en todo la sentencia condenatoria de primera instancia. \u00a0<\/p>\n<p>Precisa la Corte que en cuanto \u00a0a los fundamentos del cargo de nulidad se tiene dicho que de acuerdo \u00a0con el principio de acreditaci\u00f3n, para solicitar la \u00a0invalidaci\u00f3n del tr\u00e1mite es necesario demostrar la \u00a0existencia de una irregularidad sustancial que afecte de manera \u00a0insubsanable el debido proceso. En este caso son varias las \u00a0situaciones que el censor califica de irregulares y que por s\u00ed \u00a0solas, agrega, constituyen violaci\u00f3n del debido proceso. \u00a0<\/p>\n<p>La primera de ellas consiste en \u00a0que el Tribunal de Bucaramanga hubiera revocado la decisi\u00f3n de \u00a0la juez de conocimiento que invalid\u00f3 el sentido del fallo que \u00a0hab\u00eda sido condenatorio frente a los dos procesados, para \u00a0cambiarlo a absolutorio para uno de ellos. \u00a0<\/p>\n<p>De acuerdo con la \u00a0jurisprudencia trazada en torno a la retractaci\u00f3n del juez del \u00a0sentido del fallo, se ha dicho en reiteradas ocasiones que el \u00a0sentenciador una vez adopta su postura frente a la decisi\u00f3n \u00a0que le compete adoptar culminado el juicio, \u00e9sta lo vincula y \u00a0debe expresarla en el fallo en perfecta armon\u00eda con aquella. \u00a0<\/p>\n<p>Este ha sido un criterio \u00a0reiterado por la Corte (CSJ SP., 20 ene. 2010, rad. 32196; CSJ SP, 14 \u00a0nov. 2012, rad. 36333; CSJ SP, 25 sep. 2013, rad. 40334; CSJ SP, 23 \u00a0sep. 2015 rad. 40694; CSJ SP, 30 Nov. 2016, rad. 46819; CSJ SP, 27 \u00a0jul. 2016, rad.41429, entre otras m\u00e1s) \u00a0seg\u00fan el cual \u00a0\u00abel anuncio del \u00a0sentido del fallo por parte del juez de conocimiento, una vez \u00a0finalizado el debate p\u00fablico oral, constituye un acto procesal \u00a0que forma parte de la estructura del debido proceso y vincula al \u00a0juzgador con la decisi\u00f3n adoptada en la sentencia, conformando \u00a0con esta una unidad tem\u00e1tica inescindible. Por tanto, el fallo \u00a0conforma un todo inescindible, un acto complejo, una unidad tem\u00e1tica, \u00a0entre el anuncio p\u00fablico y la sentencia finalmente escrita, \u00a0debiendo por tanto ser coincidentes sus alcances. Sentido de fallo \u00a0que adem\u00e1s de garantizar el pronto conocimiento de la decisi\u00f3n \u00a0adoptada, resulta consecuente con los principios de inmediaci\u00f3n, \u00a0concentraci\u00f3n e inmutabilidad, que rigen el proceso penal, \u00a0razones que justifican, desde el punto de vista de la legitimidad de \u00a0la decisi\u00f3n judicial, su aspiraci\u00f3n de correcci\u00f3n \u00a0en la determinaci\u00f3n del juez de conocimiento, por lo que \u00a0resulta inconveniente en t\u00e9rminos de coherencia y seguridad \u00a0jur\u00eddica, la posibilidad que ante la variaci\u00f3n de su \u00a0criterio pudiera modificar el sentido del fallo\u00bb \u00a0<\/p>\n<p>En esa medida, ninguna \u00a0irregularidad se deriva del hecho de que la juez de conocimiento \u00a0emitiera fallo en concordancia con lo que anunci\u00f3 en audiencia \u00a0de 28 de noviembre de 2014, pues su actitud posterior de invalidar su \u00a0propia decisi\u00f3n, no pod\u00eda producir efecto alguno al ser \u00a0contraria a las bases mismas del proceso penal. \u00a0<\/p>\n<p>Lo anterior para significar que \u00a0la orden que dio el Tribunal para que la juez emitiera la sentencia \u00a0de acuerdo con el sentido que ella misma expres\u00f3 en la citada \u00a0sesi\u00f3n de audiencia, tampoco constituye una irregularidad \u00a0sustancial que afecte el debido proceso, como s\u00ed lo hubiera \u00a0sido, haber dejado inc\u00f3lume la variaci\u00f3n, tal y como lo \u00a0pretende la defensa. \u00a0<\/p>\n<p>En lo que s\u00ed acierta el \u00a0censor es en calificar como trasgresor de las formas propias del \u00a0proceso, el que la modificaci\u00f3n del criterio de la juez de \u00a0conocimiento se hubiere adoptado a trav\u00e9s de una decisi\u00f3n \u00a0interlocutoria que se notific\u00f3 a las partes, lo cual \u00a0posibilit\u00f3 la interposici\u00f3n de los recursos, con la \u00a0consecuente respuesta de la segunda instancia. \u00a0<\/p>\n<p>La Sala considera que este es \u00a0un desacierto del a \u00a0quo, en la medida en \u00a0que no pod\u00eda escindir el sentido del fallo de la sentencia, es \u00a0decir, habiendo modificado el criterio inicial, ten\u00eda que \u00a0expresarlo en la sentencia y, en ese momento, cumplida su publicidad, \u00a0correr traslado a las partes para la interposici\u00f3n de los \u00a0recursos que proceden contra el fallo, m\u00e1s no contra el \u00a0anuncio de su sentido. \u00a0<\/p>\n<p>Lo anterior habida cuenta que \u00a0como ya se indic\u00f3, la emisi\u00f3n del sentido del fallo y \u00a0la sentencia conforman una unidad inescindible y, por tanto, una sola \u00a0decisi\u00f3n que de resultar adversa a alguna de la partes, puede \u00a0ser recurrida en el momento de notificaci\u00f3n de la sentencia. \u00a0<\/p>\n<p>Empero, el desacertado tr\u00e1mite \u00a0que se otorg\u00f3 en las instancias a la controversia que gener\u00f3 \u00a0el intempestivo cambio del sentido del fallo, no provoca la \u00a0invalidaci\u00f3n del proceso, habida cuenta que la inconformidad \u00a0frente a la decisi\u00f3n de la funcionaria de primer grado, y a la \u00a0que se anticip\u00f3 la Fiscal\u00eda como consecuencia de \u00a0desatino en el procedimiento, de todas maneras se hubiera planteado \u00a0en la oportunidad para recurrir la sentencia a efecto de que fuera \u00a0resuelta por el Tribunal. Tal inconformismo necesariamente habr\u00eda \u00a0dado lugar a la invalidaci\u00f3n de la sentencia, en orden a que \u00a0\u00e9sta resultara congruente con el sentido expresado por la juez \u00a0cuando culmin\u00f3 el juicio oral. \u00a0<\/p>\n<p>As\u00ed las cosas, pese a \u00a0que la decisi\u00f3n del Tribunal de \u00abrevocar\u00bb \u00a0la decisi\u00f3n que invalid\u00f3 el anuncio del sentido del \u00a0fallo, fue producto de un error en el procedimiento, pues debi\u00f3 \u00a0diferirse para cuando tuviera que resolver la apelaci\u00f3n contra \u00a0la sentencia, se corrigi\u00f3 el craso error en el que incurri\u00f3 \u00a0la a quo, y, \u00a0en esa medida, de acuerdo con el principio de instrumentalidad que \u00a0rige la declaratoria de las nulidades, no se gener\u00f3 el agravio \u00a0que se denuncia en la demanda como causa para invalidar el proceso. \u00a0<\/p>\n<p>Otra de las situaciones que \u00a0soportan el pedido para que se anule la actuaci\u00f3n con el fin \u00a0de restablecer el derecho al debido proceso, es la referida al \u00a0impedimento en el que se ver\u00eda incursa, tanto la juez de \u00a0primer grado, como los magistrados del Tribunal que integraron la \u00a0sala que resolvi\u00f3 el recurso de apelaci\u00f3n contra la \u00a0sentencia. La primera, precisa el recurrnete, por cuanto en contrav\u00eda \u00a0de su convicci\u00f3n frente al caso, se vio compelida a emitir un \u00a0fallo adverso para Raad \u00a0Herrera pese a que \u00a0concluy\u00f3 la atipicidad de su comportamiento. Y los segundos, \u00a0porque al haber revocado la decisi\u00f3n que anul\u00f3 el \u00a0sentido del fallo, prejuzgaron el asunto al ordenar que el fallo \u00a0fuera condenatorio. \u00a0<\/p>\n<p>Es equivocado el planteamiento \u00a0del recurrente por cuanto el mismo se funda en una premisa falsa, \u00a0cual es, que es permitido que el juez de conocimiento se retracte del \u00a0sentido del fallo que ya ha anunciado. Como se indic\u00f3 en \u00a0p\u00e1ginas anteriores una vez anunciado el sentido del fallo, \u00a0\u00e9ste vincula al juez, motivo por el que, el hecho de que tenga \u00a0que ajustar la sentencia al criterio por \u00e9l mismo expresado, \u00a0no afecta su imparcialidad, por tanto, no se suscita impedimento. \u00a0<\/p>\n<p>Ahora, respecto de la falta de \u00a0imparcialidad de los magistrados que resolvieron la apelaci\u00f3n \u00a0contra el fallo condenatorio, no acredita el censor de qu\u00e9 \u00a0forma prejuzgaron el caso, simplemente sostiene que profirieron una \u00a0decisi\u00f3n interlocutoria en el tr\u00e1mite previo al fallo, \u00a0quedando as\u00ed la queja a mitad de camino. \u00a0<\/p>\n<p>El demandante se conforma con \u00a0afirmar que la segunda instancia ya hab\u00eda hecho un \u00a0pronunciamiento sobre la responsabilidad de Jadirk \u00a0Raad Herrera, sin hacer \u00a0ver a la Sala que en la decisi\u00f3n de 22 de julio de 2016 que \u00a0resolvi\u00f3 la apelaci\u00f3n del auto que invalid\u00f3 el \u00a0sentido del fallo, el Tribunal valor\u00f3 aspectos de la tipicidad \u00a0o de la responsabilidad del procesado en los hechos; tal omisi\u00f3n \u00a0configura el incumplimiento de los principios de cr\u00edtica \u00a0vinculante y sustentaci\u00f3n suficiente que gu\u00edan la \u00a0casaci\u00f3n. \u00a0<\/p>\n<p>Por el contrario, al verificar \u00a0la Sala el contendido de la citada decisi\u00f3n, advierte que la \u00a0cuesti\u00f3n resuelta se circunscribi\u00f3 al debate acerca de \u00a0la posibilidad de que el juez de conocimiento anule el sentido del \u00a0fallo por \u00e9l proferido para variarlo por otro, por manera que \u00a0la orden que dio el Tribunal para que la sentencia se emitiera \u00a0conforme al inicial criterio del a \u00a0quo, no obedeci\u00f3 \u00a0a la apreciaci\u00f3n de los hechos por \u00a0parte del ad \u00a0quem, en donde \u00a0impusiera un fallo condenatorio; la sentencia adversa que se emiti\u00f3 \u00a0en primer grado, lo fue por la mera raz\u00f3n de que el anuncio \u00a0del sentido del fallo, -que \u00a0vinculaba a la juez-, \u00a0lo fue en ese sentido. \u00a0<\/p>\n<p>Son claras las incorrecciones \u00a0en la sustentaci\u00f3n del cargo de nulidad, as\u00ed como en el \u00a0de violaci\u00f3n directa de la norma sustancial, motivo por el que \u00a0la demanda de casaci\u00f3n se inadmite. \u00a0<\/p>\n<p>3. Por \u00faltimo, \u00a0del estudio del proceso no se vislumbra violaci\u00f3n \u00a0de \u00a0 derechos \u00a0fundamentales \u00a0o \u00a0garant\u00edas \u00a0de los intervinientes, \u00a0para ejercer la \u00a0facultad \u00a0oficiosa de \u00a0\u00edndole \u00a0legal \u00a0que \u00a0al \u00a0 respecto \u00a0le \u00a0asiste \u00a0a \u00a0la \u00a0Sala. \u00a0<\/p>\n<p>4. Contra \u00a0esta decisi\u00f3n procede el mecanismo de insistencia, en los \u00a0t\u00e9rminos concretados por la Corte a partir del fallo de 12 de \u00a0septiembre de 2005 radicaci\u00f3n 24322. \u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, Sala de \u00a0Casaci\u00f3n Penal, \u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>Inadmitir \u00a0la demanda de casaci\u00f3n presentada a nombre de \u00a0Jadirk Raad Herrera. \u00a0<\/p>\n<p>Contra esta providencia procede \u00a0el mecanismo de insistencia. \u00a0<\/p>\n<p>C\u00f3piese, comun\u00edquese \u00a0y devu\u00e9lvase al Tribunal de origen. C\u00famplase. \u00a0<\/p>\n<p>LUIS ANTONIO HERN\u00c1NDEZ \u00a0BARBOSA \u00a0<\/p>\n<p>JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>JOSE LUIS BARCEL\u00d3 \u00a0CAMACHO \u00a0<\/p>\n<p>FERNANDO LEON BOLA\u00d1OS \u00a0PALACIO \u00a0<\/p>\n<p>FERNANDO ALBERTO CASTRO \u00a0CABALLERO \u00a0<\/p>\n<p>EUGENIO FERN\u00c1NDEZ \u00a0CARLIER \u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>PATRICIA SALAZAR CUELLAR \u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA \u00a0YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 FERNANDO ALBERTO CASTRO \u00a0CABALLERO \u00a0 Magistrado Ponente \u00a0 AP787-2018 \u00a0 Radicaci\u00f3n: 51609 \u00a0 Aprobado Acta N. 065 \u00a0 Bogot\u00e1, D. C., \u00a0veintiocho (28) de febrero de dos mil dieciocho (2018). \u00a0 VISTOS \u00a0 Procede \u00a0la Sala a estudiar los requisitos de adecuada fundamentaci\u00f3n \u00a0de la demanda de casaci\u00f3n promovida por la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-36473","post","type-post","status-publish","format-standard","hentry","category-27"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/36473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=36473"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/36473\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=36473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=36473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=36473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}