{"id":36287,"date":"2023-09-13T21:43:56","date_gmt":"2023-09-13T21:43:56","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap5251-201853321\/"},"modified":"2023-09-13T21:43:56","modified_gmt":"2023-09-13T21:43:56","slug":"ap5251-201853321","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap5251-201853321\/","title":{"rendered":"AP5251-2018(53321)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 \u00a0LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>Magistrado \u00a0Ponente \u00a0<\/p>\n<p>AP5251-2018 \u00a0<\/p>\n<p>Radicado n.\u00ba \u00a053321 \u00a0<\/p>\n<p>(Acta n.\u00ba \u00a0400) \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D.C., cinco (5) de diciembre de dos mil dieciocho (2018). \u00a0<\/p>\n<p>La Sala se \u00a0pronuncia sobre los requisitos de l\u00f3gica y debida \u00a0argumentaci\u00f3n de la demanda de casaci\u00f3n presentada por \u00a0el defensor de ANDERSON \u00a0FABI\u00c1N MOLINA ACOSTA y \u00a0PROCESO \u00a0RU\u00cdZ GIRALDO. \u00a0<\/p>\n<p>H \u00a0E C H O S \u00a0<\/p>\n<p>Fueron expuestos \u00a0por el Tribunal en los siguientes t\u00e9rminos: \u00a0<\/p>\n<p>\u00abOcurrieron \u00a0el 24 de mayo de 2013, en horas de la tarde, aproximadamente entre \u00a03:30 y 4:00, en la finca Rocetales, vereda La Islandia, zona rural \u00a0del municipio de Rovira, Tolima, cuando Reinel Leyton Aguilar, quien \u00a0se encontraba en compa\u00f1\u00eda de su hermano Jos\u00e9 \u00a0Jes\u00fas realizando labores agr\u00edcolas, fue interceptado \u00a0por un sujeto que se identific\u00f3 como miembro de la agrupaci\u00f3n \u00a0armada ilegal FARC, inquiri\u00e9ndole por su presencia en el sitio \u00a0sin la debida autorizaci\u00f3n, exigi\u00e9ndole que lo \u00a0acompa\u00f1ara para auxiliar otros guerrilleros que necesitaban de \u00a0su ayuda, petici\u00f3n a la que no accedi\u00f3, por lo que \u00a0dicho sujeto se acerc\u00f3 a su cong\u00e9nere haci\u00e9ndole \u00a0la misma advertencia y solicitud, momento en el cual Jos\u00e9 \u00a0Jes\u00fas se encamina en la misma direcci\u00f3n de ese extra\u00f1o, \u00a0siendo sorprendido por otro sujeto reconocido por Reinel como PROCESO \u00a0RU\u00cdZ GIRALDO, \u00a0quien sin mediar palabra le propin\u00f3 seis disparos con arma de \u00a0fuego ocasion\u00e1ndole la muerte. \u00a0<\/p>\n<p>Ante tal hecho, \u00a0Reinel Leyton Aguilar huy\u00f3 del lugar en busca de un sitio \u00a0donde pudiera comunicarse telef\u00f3nicamente para dar aviso de lo \u00a0sucedido, fue as\u00ed como alertada la polic\u00eda se realiz\u00f3 \u00a0un operativo en el lugar conocido como \u201cLa Y\u201d, kil\u00f3metro \u00a07 que de la vereda conduce al casco urbano de Rovira, que culmin\u00f3 \u00a0con la captura de PROCESO \u00a0RU\u00cdZ GIRALDO, \u00a0a quien se le hall\u00f3 un arma de fuego tipo rev\u00f3lver \u00a0calibre 38, marca S &amp; W, con seis cartuchos en el tambor y \u00a0catorce cartuchos de similar calibre en el bolsillo de su pantal\u00f3n \u00a0y de ANDERSON \u00a0FABI\u00c1N MOLINA ACOSTA, \u00a0conductor de la motocicleta de placa NFY 83 A. \u00a0<\/p>\n<p>Con \u00a0posterioridad a la captura, Reinel Leyton Giraldo reconoce a RU\u00cdZ \u00a0GIRALDO y \u00a0a MOLINA \u00a0ACOSTA \u00a0como los responsables de la muerte de su hermano\u00bb. \u00a0<\/p>\n<p>A \u00a0N T E C E D E N T E S \u00a0<\/p>\n<p>1. Culminada la \u00a0fase del juicio y anunciado el sentido del fallo por el Juzgado \u00a0Quinto Penal del Circuito de Ibagu\u00e9 (Tolima), estrado judicial \u00a0al que correspondieron las diligencias, se dict\u00f3 sentencia el \u00a010 de noviembre de 2017, mediante la cual se le impuso a PROCESO \u00a0RU\u00cdZ GIRALDO y \u00a0ANDERSON \u00a0FABI\u00c1N MOLINA ACOSTA la \u00a0pena principal de prisi\u00f3n por treinta y siete (37) a\u00f1os \u00a0y seis (6) meses y la accesoria de inhabilitaci\u00f3n para el \u00a0ejercicio de derechos y funciones p\u00fablicas por veinte (20) \u00a0a\u00f1os, al hall\u00e1rseles coautores responsables de la \u00a0conducta punible de homicidio agravado (art\u00edculos 103 y 104, \u00a0numeral 7.\u00ba, del C\u00f3digo Penal). En la misma decisi\u00f3n, \u00a0se les absolvi\u00f3 por el delito de fabricaci\u00f3n, tr\u00e1fico, \u00a0porte o tenencia de armas de fuego, accesorios, partes o municiones \u00a0agravado (art\u00edculos 365, numerales 1.\u00ba y 5.\u00ba, \u00a0ib\u00eddem), neg\u00e1ndoseles la suspensi\u00f3n condicional \u00a0de la ejecuci\u00f3n de la pena y la prisi\u00f3n domiciliaria.1 \u00a0<\/p>\n<p>2. Apelada esta \u00a0determinaci\u00f3n por la defensa, fue confirmada por el Tribunal \u00a0Superior del Distrito Judicial de Ibagu\u00e9 -Sala Penal- el 17 de \u00a0mayo de 2018.2 \u00a0<\/p>\n<p>LA DEMANDA DE \u00a0CASACI\u00d3N \u00a0<\/p>\n<p>El demandante \u00a0luego de rese\u00f1ar los hechos, la actuaci\u00f3n procesal \u00a0surtida e identificar las partes e intervinientes, as\u00ed como la \u00a0sentencia recurrida, postula un cargo \u00a0\u00fanico en \u00a0contra del fallo de segunda instancia al amparo de la causal tercera \u00a0del art\u00edculo 181 de la Ley 906 de 2004, denunciando el \u00a0desconocimiento de las reglas de apreciaci\u00f3n de la prueba por \u00a0falso raciocinio, \u00ablo \u00a0cual origina, a su vez, nulidad de dicha providencia, conforme a lo \u00a0dispuesto en el inciso primero del art. 457 de la codificaci\u00f3n \u00a0procesal penal citada, por afectaci\u00f3n de su validez jur\u00eddica\u00bb. \u00a0<\/p>\n<p>Lo anterior, toda \u00a0vez que los juzgadores apoyaron la condena en la declaraci\u00f3n \u00a0de Reinel Leyton Aguilar quien asever\u00f3 que dos personas que lo \u00a0abordaron a \u00e9l y a su hermano mientras se dedicaban a labores \u00a0del campo, anunci\u00e1ndose como miembros de la guerrilla, le \u00a0causaron la muerte a \u00e9ste \u00faltimo, pero el relato en \u00a0concepto del casacionista, da lugar a estas inquietudes: \u00a0<\/p>\n<p>i) El testigo \u00a0\u00abantes \u00a0que prestarle auxilio a su hermano Jos\u00e9 Jes\u00fas Leyton \u00a0Aguilar o de repeler el ataque del que se le hizo v\u00edctima, con \u00a0lo que tuviera a mano, resolvi\u00f3 buscar refugio entre los \u00a0vecinos de la regi\u00f3n, quienes, advertidos ya de la situaci\u00f3n, \u00a0llamaron a las autoridades del municipio de Rovira para que tomaran \u00a0las medidas del caso, como en efecto sucedi\u00f3\u00bb. \u00a0<\/p>\n<p>ii) \u00abNo \u00a0se\u00f1al\u00f3 ante los vecinos de la regi\u00f3n a los dos \u00a0sujetos de sexo masculino que hicieron presencia en la finca \u00a0\u201cRocetales\u201d [&#8230;] por sus nombres de pila o por otras \u00a0caracter\u00edsticas que llevaran a su individualizaci\u00f3n y, \u00a0por esta raz\u00f3n, quienes llamaron a las autoridades haciendo \u00a0uso de tel\u00e9fonos celulares no mencionaron a nadie por su \u00a0nombre o por sus caracter\u00edsticas individuales, indicando, eso \u00a0s\u00ed, que se desplazaban en una motocicleta\u00bb. \u00a0Circunstancia \u00a0que estima relevante, pues el declarante, testigo \u00fanico, \u00a0afirm\u00f3 que conoc\u00eda de vieja data a RUIZ \u00a0GIRALDO por \u00a0ser ambos oriundos de Anzo\u00e1tegui, no obstante, reitera, \u00aben \u00a0ning\u00fan momento cit\u00f3 a dicho acusado como el autor de \u00a0los disparos\u00bb. \u00a0<\/p>\n<p>iii) Esta omisi\u00f3n \u00a0llev\u00f3 a que al ser aprehendidos los implicados por la polic\u00eda, \u00a0tan solo se les retuviera porque el mencionado llevaba consigo un \u00a0rev\u00f3lver junto con varios cartuchos sin permiso de autoridad \u00a0competente, de ah\u00ed que se les judicializara sin tenerse en \u00a0cuenta para esos efectos la comisi\u00f3n del homicidio materia de \u00a0diligencias. Esto condujo a que la fuerza p\u00fablica, \u00abno \u00a0hubiera embalado y amparado con cadena de custodia el rev\u00f3lver \u00a0para determinar luego, por examen de laboratorio, si hab\u00eda \u00a0sido recientemente disparado y tampoco se embalaron las manos de \u00a0\u00e9stos para que de inmediato se les hubiera practicado (sic) el \u00a0examen de guantelete de parafina en direcci\u00f3n a establecer si \u00a0hab\u00edan hecho uso de armas de fuego\u00bb. \u00a0<\/p>\n<p>De igual modo, \u00a0trae a colaci\u00f3n c\u00f3mo la defensa obtuvo las prendas de \u00a0vestir que tra\u00eda consigo RU\u00cdZ \u00a0GIRALDO para \u00a0ese instante a fin de someterlas a pruebas t\u00e9cnicas por parte \u00a0de una experta, quien concluy\u00f3 que no hab\u00eda en ellas \u00a0vestigios de p\u00f3lvora y estableci\u00f3 la falta de \u00a0concordancia de la trayectoria de los disparos en el cuerpo del \u00a0obitado con relaci\u00f3n a lo narrado sobre el particular por el \u00a0deponente. As\u00ed mismo, cita la versi\u00f3n de testigos que \u00a0informaron de la presencia de sus asistidos en un sitio distante a \u00a0aquel donde ocurrieron los hechos. \u00a0<\/p>\n<p>Por consiguiente, \u00a0asegura, el ad \u00a0quem incurri\u00f3 \u00a0en \u00aberror \u00a0de hecho por falso juicio de convicci\u00f3n\u00bb, toda \u00a0vez que Reinel Leyton Aguilar se\u00f1al\u00f3 c\u00f3mo el \u00a0agresor de su hermano le dispar\u00f3 cuatro veces por la espalda \u00a0con un rev\u00f3lver, empero, despu\u00e9s asegur\u00f3 que \u00a0fueron seis los disparos, propinados con una pistola, recabando en \u00a0las imprecisiones anotadas con antelaci\u00f3n. En consecuencia, \u00a0considera vulnerados los postulados de la sana cr\u00edtica al no \u00a0aplicarse las reglas de la ciencia, en cuanto a las pericias a las \u00a0que debi\u00f3 ser sometida el arma de fuego incautada durante el \u00a0procedimiento de captura, y los principios de la l\u00f3gica, en \u00a0concreto, los de identidad y raz\u00f3n suficiente, relativos a que \u00a0todo objeto es id\u00e9ntico a s\u00ed mismo y como todo juicio \u00a0requiere de un fundamento, respectivamente. \u00a0<\/p>\n<p>En estas \u00a0condiciones, al resultar la sentencia \u00abnula \u00a0por virtud de lo dispuesto [&#8230;] en el inciso primero del art. 457 \u00a0del C\u00f3digo de Procedimiento Penal (Ley 906 de 2004)\u00bb, \u00a0solicita \u00a0que se case y \u00abse \u00a0ordene el archivo del proceso, previa cancelaci\u00f3n de las \u00a0\u00f3rdenes de captura impartidas contra los acusados\u00bb. \u00a0<\/p>\n<p>\u00a0 \u00a0 CONSIDERACIONES \u00a0 DE \u00a0LA \u00a0CORTE \u00a0<\/p>\n<p>1. La casaci\u00f3n, \u00a0seg\u00fan lo ha decantado la jurisprudencia, no es una tercera \u00a0instancia de la actuaci\u00f3n penal ni un escenario propicio para \u00a0disentir de cualquier manera de la interpretaci\u00f3n normativa o \u00a0de la valoraci\u00f3n probatoria realizada por el juzgador, tampoco \u00a0para detectar cualquier clase de irregularidad en el proceso. El \u00a0recurso extraordinario y la intervenci\u00f3n de la Corte conforme \u00a0el principio de limitaci\u00f3n, por regla general, se restringe a \u00a0constatar si la demanda contentiva de la impugnaci\u00f3n acredita \u00a0vicios ostensibles y trascendentes, sintetizados de forma taxativa en \u00a0las causales legales que lo hacen procedente, para este evento, las \u00a0del art\u00edculo 181 de la Ley 906 de 2004. \u00a0<\/p>\n<p>El censor no debe \u00a0perder de vista que la l\u00f3gica del tr\u00e1mite se refleja en \u00a0dichas causales y que los deberes de una correcta postulaci\u00f3n \u00a0y adecuada fundamentaci\u00f3n tienen su raz\u00f3n de ser en que \u00a0el recurso es de naturaleza rogada, por ende, la simple discrepancia \u00a0de criterios no es un aspecto con la viabilidad de ser auscultado en \u00a0esta sede (Cfr. CSJ AP, 18 ago. 2010, rad. 33559). \u00a0<\/p>\n<p>2. Bajo esta \u00a0perspectiva, se anuncia la inadmisi\u00f3n \u00a0del libelo atendiendo que en lugar de ajustarse a los presupuestos \u00a0demarcados en precedencia, se restringe a plasmar la llana \u00a0divergencia del casacionista con las conclusiones de los juzgadores, \u00a0pas\u00e1ndose por alto la l\u00f3gica que reg\u00eda la \u00a0adecuada presentaci\u00f3n del caso si se pretend\u00eda suscitar \u00a0su conocimiento por parte de la Sala. Las siguientes, son las razones \u00a0de ese diagn\u00f3stico: \u00a0<\/p>\n<p>2.1. En lo formal, \u00a0el cargo \u00a0\u00fanico es \u00a0confuso porque respecto de la misma prueba, el testimonio de Reinel \u00a0Leyton Aguilar, se plantea sin distinci\u00f3n alguna falso \u00a0raciocinio, falso juicio de convicci\u00f3n y nulidad, modalidades \u00a0de error que difieren en su naturaleza y sus efectos. Entonces, ha de \u00a0recordarse que mientras el primero se refiere a un vicio de \u00a0apreciaci\u00f3n probatoria por razones de hecho, \u00a0esto \u00a0es, por transgresi\u00f3n de la sana cr\u00edtica como m\u00e9todo \u00a0de libre formaci\u00f3n del conocimiento (CSJ AP 3794-2018), el \u00a0segundo se relaciona con un dislate de derecho \u00a0por \u00a0apartarse el sentenciador de la tarifa legal preestablecida para la \u00a0valoraci\u00f3n, infracci\u00f3n de car\u00e1cter restringido y \u00a0circunscrita en la Ley 906 de 2004, prima \u00a0facie, a \u00a0la prohibici\u00f3n de dictar condena con base exclusiva en prueba \u00a0de referencia (CSJ AP 3642-2018). Mientras que el \u00faltimo, se \u00a0asocia al quebranto de la estructura \u00a0formal \u00a0del proceso penal o la lesi\u00f3n a las garant\u00edas \u00a0de \u00a0las partes o intervinientes (CSJ AP 3645-2018). \u00a0<\/p>\n<p>En consecuencia, \u00a0la conceptualizaci\u00f3n de cada uno de estos yerros exclu\u00eda \u00a0su postulaci\u00f3n conjunta, de modo que no se avizora con \u00a0claridad cu\u00e1l fue la supuesta incorrecci\u00f3n en la que \u00a0incurri\u00f3 el Tribunal. A lo que se suma que el reparo omite la \u00a0proposici\u00f3n jur\u00eddica completa, al no se\u00f1alar \u00a0consistentemente cu\u00e1l o cu\u00e1les fueron las normas \u00a0sustanciales conculcadas, solo se citan de manera ca\u00f3tica \u00a0preceptos atinentes al \u00e1mbito probatorio en general (art\u00edculos \u00a0372 y siguientes ib\u00eddem) y el art\u00edculo 457 \u00eddem, \u00a0relativo a la invalidez del tr\u00e1mite. \u00a0<\/p>\n<p>2.2. Ahora, aun \u00a0obviando tales falencias y asumiendo que el reproche se orienta a \u00a0evidenciar trat\u00e1ndose de la dicci\u00f3n en comento la \u00a0existencia de un falso raciocinio, la presunta lesi\u00f3n a las \u00a0reglas de la ciencia y los principios de la l\u00f3gica alegada en \u00a0ese sentido no trasciende al mero enunciado, en tanto el ataque se \u00a0orienta a refutar met\u00f3dicamente, con base exclusiva en la \u00a0diferencia de criterios, el alcance concedido a la declaraci\u00f3n \u00a0de Reinel Leyton Aguilar. En este aspecto, hay que destacar c\u00f3mo \u00a0en el libelo se pretermite deliberadamente lo dicho en la providencia \u00a0impugnada acerca del particular, donde se anot\u00f3: \u00a0<\/p>\n<p>\u00ab[&#8230;] su \u00a0narraci\u00f3n adquiere especial importancia, d\u00e1ndose como \u00a0demostrado y probado los hechos tal y como fueron se\u00f1alados: \u00a0\u201cyo estaba trabajando con mi hermano, \u00e9l estaba como a \u00a0unos 50 mts. y ANDERSON \u00a0FABI\u00c1N MOLINA me \u00a0lleg\u00f3, pero yo no sab\u00eda qui\u00e9n era, me dijo que \u00a0si yo era el patr\u00f3n, yo le dije que no, que yo no era el \u00a0patr\u00f3n que fuera a la casa que los patrones estaban all\u00e1 \u00a0y entonces me dijo que por qu\u00e9 nos hab\u00edamos metido a la \u00a0finca sin permiso de ellos, que ellos eran de la guerrilla y que \u00a0hab\u00edan 30 guerrilleros en La Gaviota, en una finquita que \u00a0queda al otro lado, que para que fuera yo a subir unas cargas, \u00a0entonces yo le dije no vaya y hable con los patrones porque yo no soy \u00a0el patr\u00f3n, entonces se dirigi\u00f3 donde mi hermano y \u00a0entonces ah\u00ed estaban hablando con mi hermano y yo le dije a mi \u00a0hermano que no bajara y \u00e9l entonces le dijo que fuera a hablar \u00a0con el comandante, \u00e9l sigui\u00f3 adelantico cuando sali\u00f3 \u00a0PROCESO \u00a0y \u00a0le dispar\u00f3\u201d [&#8230;]. \u00a0<\/p>\n<p>[&#8230;] El \u00a0aceptar que a MOLINA \u00a0ACOSTA \u00a0lo vio por primera vez ese 24 de mayo de 2013, denota en el \u00a0declarante espontaneidad y franqueza en su relato, sin adiciones, \u00a0hechos o datos agregados para pretender darle mayor credibilidad a su \u00a0narrativa, \u00fanicamente su conocimiento y percepci\u00f3n \u00a0directa de lo que fue el acontecer tr\u00e1gico, veracidad que no \u00a0se nubla con lo referido por los testigos de descargo Jos\u00e9 \u00a0Augusto Acosta Gonz\u00e1lez, Luis Gonzalo Giraldo Arbel\u00e1ez \u00a0y Luz Nirida Ru\u00edz Giraldo, quienes intentaron infructuosamente \u00a0ubicar a RUIZ \u00a0GIRALDO y \u00a0MOLINA \u00a0ACOSTA en \u00a0un sitio completamente distante o alejado geogr\u00e1ficamente de \u00a0la vereda La Islandia del municipio de Rovira, pretendiendo demostrar \u00a0que les era imposible estar en el lugar del homicidio, tesis de la \u00a0defensa que no sale avante pues respecto del testimonio de Acosta \u00a0Gonz\u00e1lez [&#8230;], no puede dar fe absoluta de d\u00f3nde se \u00a0encontraba su sobrino, \u00fanicamente habl\u00f3 con ANDERSON \u00a0FABI\u00c1N telef\u00f3nicamente, \u00a0indic\u00e1ndole \u00e9ste que se encontraba en compa\u00f1\u00eda \u00a0de una mujer y que por esa raz\u00f3n no lo visitar\u00eda, lo \u00a0que deja entrever la fragilidad y debilidad del relato, pues n\u00f3tese \u00a0que MOLINA \u00a0ACOSTA no \u00a0se encontraba con una mujer como al parecer inform\u00f3, sino con \u00a0RU\u00cdZ \u00a0GIRALDO. \u00a0<\/p>\n<p>Ahora, Luis \u00a0Gonzalo Giraldo Arbel\u00e1ez relata haber visto a su sobrino hasta \u00a0el mediod\u00eda del 24 de mayo cuando se march\u00f3 de su casa \u00a0sin indicar cu\u00e1l fue el rumbo que tom\u00f3 PROCESO \u00a0y \u00a0Luz Nirida solo tiene conocimiento que el 23 de mayo cuando su \u00a0hermano PROCESO \u00a0estuvo \u00a0en su casa, al d\u00eda siguiente ninguna comunicaci\u00f3n \u00a0sostuvo con \u00e9l, por lo que sus afirmaciones resultan \u00a0insustanciales respecto de la ubicaci\u00f3n de los acusados para \u00a0la noche del homicidio. \u00a0<\/p>\n<p>Esos ingentes \u00a0esfuerzos de los testigos y la defensa, se desvanecen con el hecho \u00a0cierto y demostrado que PROCESO \u00a0RU\u00cdZ GIRALDO y \u00a0ANDERSON \u00a0FABI\u00c1N MOLINA ACOSTA la \u00a0noche del 24 de mayo de 2013, fueron sorprendidos y ubicados por \u00a0personal de la polic\u00eda de vigilancia en el sitio conocido como \u00a0\u201cLa Y\u201d, kil\u00f3metro 7 que del casco urbano del \u00a0municipio de Rovira conduce a la vereda La Islandia. \u00a0<\/p>\n<p>Tal \u00a0circunstancia permite proporcionarle mayor valor al testimonio de \u00a0Reinel Leyton Aguilar, en la medida que es dicho testigo quien los \u00a0ubica en la zona, confirm\u00e1ndose efectivamente por personal de \u00a0la polic\u00eda su presencia en el lugar\u00bb.3 \u00a0<\/p>\n<p>Y en el fallo de \u00a0primer grado que constituye una unidad jur\u00eddica inescindible \u00a0con el del ad \u00a0quem en \u00a0todo aquello que no se contradigan, adem\u00e1s de rese\u00f1arse \u00a0como exist\u00edan antecedentes de disputas entre la familia \u00a0Bautista (a la cual era cercano RU\u00cdZ \u00a0GIRALDO) \u00a0y \u00a0la familia Leyton Aguilar que ocasionaron varias muertes violentas, \u00a0al igual que el desplazamiento de esta \u00faltima del municipio de \u00a0Anzo\u00e1tegui hasta Rovira, se consign\u00f3: \u00a0<\/p>\n<p>\u00abSobre \u00a0la atribuci\u00f3n de responsabilidad penal a los acusados, el \u00a0testigo en el juicio fue enf\u00e1tico en referir que los autores \u00a0del homicidio de su hermano [&#8230;] fueron \u201cPROCESO \u00a0RU\u00cdZ GIRALDO y \u00a0ANDERSON \u00a0FABI\u00c1N MOLINA ACOSTA\u201d \u00a0(Min: 25:42); se\u00f1alamiento que en forma clara, segura y \u00a0contundente siempre ha permanecido inc\u00f3lume desde el d\u00eda \u00a0de los hechos cuando se produjo la captura de estos dos ciudadanos, \u00a0\u201cy entonces los capturaron y yo baj\u00e9 al reconocimiento y \u00a0yo los reconoc\u00ed, como a las 5:30 de la ma\u00f1ana yo baj\u00e9 \u00a0all\u00e1\u00bb (Min: 28:23)\u00bb.4 \u00a0<\/p>\n<p>De este modo, se \u00a0advierte c\u00f3mo los cuestionamientos del censor se circunscriben \u00a0a un an\u00e1lisis paralelo en punto de la manera en la que, en su \u00a0concepto, debieron sopesarse las pruebas, obviando que la validez \u00a0persuasiva del relato de Reinel Leyton Aguilar no estaba sometida a \u00a0condicionamientos especiales, verbi \u00a0gratia, que \u00a0tuviese que comunicar los hechos de sangre de una forma espec\u00edfica \u00a0a sus vecinos. Tampoco la coartada edificada por los implicados por \u00a0conducto de sus familiares deb\u00eda ser acogida sin recelo alguno \u00a0por parte de la judicatura, pese a lo endeble de la misma, en los \u00a0t\u00e9rminos transcritos con antelaci\u00f3n, ni era \u00a0insoslayable realizar pruebas de residuos de disparos sobre las \u00a0prendas de los acusados con miras a determinar su responsabilidad \u00a0penal, por la ausencia, se recalca, de tarifa legal. \u00a0<\/p>\n<p>En esa secuencia, \u00a0surge que en lugar de acometerse la demostraci\u00f3n de yerros \u00a0relevantes en los razonamientos que llevaron a proferir condena, lo \u00a0que se hizo fue replicar una tesis exculpativa ya analizada y \u00a0descartada, sin que sea la Corte una instancia residual y adicional a \u00a0las ordinarias del proceso en la que sea propicio allegar un discurso \u00a0de libre confecci\u00f3n, a la expectativa de que dicha opini\u00f3n \u00a0obtenga respuesta favorable. \u00a0<\/p>\n<p>Desde esa \u00f3ptica, \u00a0las cr\u00edticas elevadas en la demanda son inanes considerando \u00a0que la alegada discordancia en la trayectoria de los disparos \u00a0cotejada con la versi\u00f3n de cargo no lo fue tal5 \u00a0y aun as\u00ed, en gracia a discusi\u00f3n, se calific\u00f3 \u00a0intrascendente.6 \u00a0De igual modo, la exigencia de que Reinel Leyton Aguilar adoptara una \u00a0actitud defensiva \u00abcon \u00a0lo que tuviera a mano\u00bb para \u00a0repeler un ataque con armas de fuego, no solo es absurda sino que se \u00a0descart\u00f3 por cuenta del examen espec\u00edfico de las \u00a0circunstancias que rodearon los sucesos7 \u00a0y sobre si la agresi\u00f3n ocurri\u00f3 con pistola o rev\u00f3lver, \u00a0tem\u00e1tica en la que se impugn\u00f3 la credibilidad de su \u00a0declaraci\u00f3n, se estudiaron detalladamente los motivos por los \u00a0que esa disparidad se ofrec\u00eda irrelevante,8 \u00a0en especial, porque la dicci\u00f3n se compaginaba con otros \u00a0elementos de juicio aportados a las diligencias. Adicionalmente, el \u00a0experticio de la perito de la defensa que recay\u00f3 en las \u00a0prendas de RU\u00cdZ \u00a0GIRALDO \u00a0se desech\u00f3 por fallas manifiestas en su cadena de custodia, \u00a0aunado a la falta de confiabilidad del resultado como factor \u00a0indicativo inexorable de ausencia de responsabilidad.9 \u00a0<\/p>\n<p>Por contera, es \u00a0palmario que las cr\u00edticas elevadas derivan en diatribas \u00a0infundadas que solo tienen respaldo en una postura subjetiva y ante \u00a0esta clase de divergencia de pareces frente a lo decidido, prevalece \u00a0la presunci\u00f3n de acierto y legalidad que cobija a los \u00a0prove\u00eddos proferidos por la administraci\u00f3n de justicia. \u00a0<\/p>\n<p>De hecho, muestra \u00a0fehaciente del desconocimiento del recurrente con respecto a la \u00a0naturaleza de la casaci\u00f3n, se encuentra en la alusi\u00f3n \u00a0realizada trat\u00e1ndose de las leyes de la ciencia cuyo \u00a0acatamiento vincula a la presunta necesidad de agotar ciertas pruebas \u00a0de laboratorio de cara a los delitos investigados, lo cual pasa por \u00a0alto el principio de libertad probatoria y c\u00f3mo las mismas se \u00a0ajustan a enunciados contrastables en el mundo emp\u00edrico, a\u00fan \u00a0no refutados (CSJ SP 1786-2018), m\u00e1s que a par\u00e1metros \u00a0de pertinencia o conducencia demostrativa. Y la referencia efectuada \u00a0con relaci\u00f3n a los \u00a0principios de la l\u00f3gica, no trasciende a la llana cita de los \u00a0axiomas de identidad y raz\u00f3n suficiente, sin explicarse c\u00f3mo \u00a0estas pautas de construcci\u00f3n intelectiva fueron empleadas en \u00a0las decisiones atacadas ni el modo en que resultaron hipot\u00e9ticamente \u00a0vulneradas. \u00a0<\/p>\n<p>3. Recapitulando, \u00a0el cargo formulado no supera una mera \u00a0opini\u00f3n indefinida, presentada a la manera de un alegato de \u00a0instancia, que omite concretar y evidenciar la clase de error que \u00a0invoca, \u00a0por lo que se dispondr\u00e1, seg\u00fan se anticip\u00f3, la \u00a0inadmisi\u00f3n \u00a0de la demanda. Adem\u00e1s, \u00a0porque \u00a0tampoco \u00a0se observa violaci\u00f3n a las garant\u00edas fundamentales que \u00a0conduzca a superar los defectos del libelo, \u00a0ni se percibe de su contexto que se precise de un fallo para cumplir \u00a0con alguna de las finalidades del recurso. \u00a0<\/p>\n<p>4. \u00a0Por \u00faltimo, debe recordarse que frente a esta providencia \u00a0procede el mecanismo de insistencia de acuerdo con los lineamientos \u00a0se\u00f1alados en el auto del 12 de diciembre de 2005, emitido en \u00a0el radicado 24322. \u00a0<\/p>\n<p>En m\u00e9rito \u00a0de lo expuesto, la CORTE \u00a0SUPREMA DE JUSTICIA, SALA DE CASACI\u00d3N PENAL, \u00a0<\/p>\n<p>R E S U E L V E \u00a0<\/p>\n<p>INADMITIR \u00a0la demanda de casaci\u00f3n allegada por el defensor de ANDERSON \u00a0FABI\u00c1N MOLINA ACOSTA y \u00a0PROCESO \u00a0RU\u00cdZ GIRALDO. \u00a0<\/p>\n<p>Contra esta \u00a0decisi\u00f3n procede el mecanismo de insistencia \u00a0<\/p>\n<p>C\u00f3piese, \u00a0comun\u00edquese y c\u00famplase \u00a0<\/p>\n<p>LUIS ANTONIO \u00a0HERN\u00c1NDEZ BARBOSA \u00a0<\/p>\n<p>Presidente \u00a0<\/p>\n<p>JOS\u00c9 \u00a0FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>JOS\u00c9 \u00a0LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>FERNANDO \u00a0ALBERTO CASTRO CABALLERO \u00a0<\/p>\n<p>EUGENIO \u00a0FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>EYDER PATI\u00d1O \u00a0CABRERA \u00a0<\/p>\n<p>PATRICIA \u00a0SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>LUIS GUILLERMO \u00a0SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA YOLANDA \u00a0NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. Folio 133 cuaderno \u00a0 \u00a0 \u00a0 \u00a0 \u00a0actuaci\u00f3n 2. \u00a0<\/p>\n<p>2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. Fl. 200 ib\u00eddem. \u00a0<\/p>\n<p>3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. Fl. 21 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y s.s sentencia de segunda instancia \/ Fl. 180 y s.s c.a 2. \u00a0<\/p>\n<p>4 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. Fl. 10 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sentencia primera instancia \/ Fl. 124 c.a 2 \u00a0<\/p>\n<p>5 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00abN\u00f3tese \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que Reinel se\u00f1al\u00f3 que a su hermano le propinaron 6 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0impactos, indicando una trayectoria as\u00ed: \u201cel (Jos\u00e9 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jes\u00fas) iba de espalda, le dispar\u00f3 (PROCESO) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y \u00e9l cay\u00f3 de medio lado y le dispar\u00f3 los otros \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de frente&#8230; ya iba cayendo\u201d, versi\u00f3n que no se \u00a0 \u00a0 \u00a0 \u00a0 \u00a0contradice con lo observado en el protocolo de necropsia [&#8230;] ni \u00a0 \u00a0 \u00a0 \u00a0 \u00a0con lo dictaminado por la perito de la defensa, pues resulta ser \u00a0 \u00a0 \u00a0 \u00a0 \u00a0cierto y demostrado que Jos\u00e9 Jes\u00fas recibi\u00f3 dos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0impactos en regi\u00f3n posterior, una en el hemit\u00f3rax \u00a0 \u00a0 \u00a0 \u00a0 \u00a0posterior en regi\u00f3n central a nivel intraescapular y otro en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la regi\u00f3n lumbar derecha, siendo los dem\u00e1s impactos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0restantes en la regi\u00f3n anterior como son hemit\u00f3rax \u00a0 \u00a0 \u00a0 \u00a0 \u00a0izquierdo, hipocondrio derecho, hipocondrio izquierdo y flanco \u00a0 \u00a0 \u00a0 \u00a0 \u00a0izquierdo [&#8230;]\u00bb (Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Fl. 26 \/ Fl. 175 ib\u00eddem). \u00a0<\/p>\n<p>6 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00ab[&#8230;] si estos al \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ser descritos de manera profesional no guardan una precisa \u00a0 \u00a0 \u00a0 \u00a0 \u00a0correspondencia con la ubicaci\u00f3n que el testigo pueda ofrecer \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de PROCESO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0RU\u00cdZ GIRALDO, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0esto es si estaba en una posici\u00f3n inferior o inclinada \u00a0 \u00a0 \u00a0 \u00a0 \u00a0respecto a Jos\u00e9 Jes\u00fas, resulta apenas natural y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0entendible (sic) si en cuenta \u00a0 \u00a0 \u00a0 \u00a0 \u00a0se tiene los \u00a0 \u00a0 \u00a0 \u00a0 \u00a0pormenores del suceso, la angustia reflejada por el testigo que lo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0hizo huir de inmediato del lugar, que la agresi\u00f3n sucede en \u00a0 \u00a0 \u00a0 \u00a0 \u00a0cuesti\u00f3n de segundos y que desde luego, Leyton Aguilar narra \u00a0 \u00a0 \u00a0 \u00a0 \u00a0lo sucedido de manera espont\u00e1nea, tal \u00a0y como lo observ\u00f3, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sin que sea dable exigirle al testigo conocimientos precisos y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0tecnicismos para que describa una ubicaci\u00f3n o trayectoria\u00bb \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(Cfr. Fl. 27 \/ Fl. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0174 \u00eddem). \u00a0<\/p>\n<p>7 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00abse trataba del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0tercer hermano que mor\u00eda en similares condiciones \u201cme \u00a0 \u00a0 \u00a0 \u00a0 \u00a0hab\u00edan matado tres hermanos, c\u00f3mo me iba a devolver\u201d \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(Min: 50:07)\u00bb. (Cfr. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Fl. 12 sentencia primera instancia \/ Fl. 122 c.a 2). \u00a0<\/p>\n<p>8 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00ab[&#8230;] esta \u00a0 \u00a0 \u00a0 \u00a0 \u00a0impugnaci\u00f3n de credibilidad no tiene la entidad objetiva para \u00a0 \u00a0 \u00a0 \u00a0 \u00a0enfilar un reproche contra vicios de sinceridad o de mentira del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0testigo, m\u00e1xime si en cuenta se tiene que se trata de una \u00a0 \u00a0 \u00a0 \u00a0 \u00a0persona con nivel acad\u00e9mico de segundo grado de primaria \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(Min: 24:32), con escaso conocimiento en armas de fuego, quien ha \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dedicado toda su vida a labores agr\u00edcolas; mal har\u00eda \u00a0 \u00a0 \u00a0 \u00a0 \u00a0exigir por parte de este despacho la identificaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0incontrastable del tipo de arma que portaba el se\u00f1or PROCESO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0RU\u00cdZ GIRALDO al \u00a0 \u00a0 \u00a0 \u00a0 \u00a0momento de los hechos\u00bb (ib\u00eddem). \u00a0<\/p>\n<p>9 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cfr. Fl. 24 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0y s.s sentencia de segunda instancia \/ Fl. 177 y s.s c.a 2). \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0 JOS\u00c9 \u00a0LUIS BARCEL\u00d3 CAMACHO \u00a0 Magistrado \u00a0Ponente \u00a0 AP5251-2018 \u00a0 Radicado n.\u00ba \u00a053321 \u00a0 (Acta n.\u00ba \u00a0400) \u00a0 Bogot\u00e1, \u00a0D.C., cinco (5) de diciembre de dos mil dieciocho (2018). \u00a0 La Sala se \u00a0pronuncia sobre los requisitos de l\u00f3gica y debida \u00a0argumentaci\u00f3n de la demanda de casaci\u00f3n presentada por \u00a0el defensor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-36287","post","type-post","status-publish","format-standard","hentry","category-27"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/36287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=36287"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/36287\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=36287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=36287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=36287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}