{"id":33861,"date":"2023-09-13T19:42:44","date_gmt":"2023-09-13T19:42:44","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap7606-201649116\/"},"modified":"2023-09-13T19:42:44","modified_gmt":"2023-09-13T19:42:44","slug":"ap7606-201649116","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap7606-201649116\/","title":{"rendered":"AP7606-2016(49116)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 PATRICIA SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>MAGISTRADA \u00a0PONENTE \u00a0\u00a0<\/p>\n<p>AP7606-2016 \u00a0\u00a0<\/p>\n<p>Radicaci\u00f3n \u00a0 \u00a0No.: \u00a049116 \u00a0\u00a0<\/p>\n<p>Acta \u00a0 \u00a0 \u00a0No. \u00a0346 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D. C.,\u00a0 dos (2) de noviembre de \u00a0dos mil diecis\u00e9is (2016). \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>De conformidad con lo previsto en el art\u00edculo \u00a075, \u00a0numeral 4\u00b0 de la Ley 600 de 2000, la Corte dirime el conflicto negativo de \u00a0competencia \u00a0que se ha suscitado entre los Juzgados 1\u00ba de Ejecuci\u00f3n de Penas y \u00a0Medidas \u00a0de Seguridad de Villavicencio y 7\u00ba de Ejecuci\u00f3n de Penas y Medidas de \u00a0Seguridad \u00a0de \u00a0Bogot\u00e1, \u00a0en \u00a0virtud \u00a0del \u00a0cual las citadas dependencias reh\u00fasan \u00a0conocer \u00a0 la \u00a0 fase \u00a0 de \u00a0 ejecuci\u00f3n \u00a0 de \u00a0 la \u00a0pena \u00a0impuesta \u00a0a \u00a0RAMIRO \u00a0 ALBERTO \u00a0HERN\u00c1NDEZ \u00a0TORRES \u00a0y \u00a0a \u00a0JOS\u00c9 FREDY SOSA MONTEALEGRE, \u00a0condenados \u00a0por \u00a0los \u00a0delitos de secuestro simple y concierto para delinquir con \u00a0fines de homicidio y conformaci\u00f3n de grupos armados ilegales. \u00a0\u00a0<\/p>\n<p>ANTECEDENTES PROCESALES \u00a0<\/p>\n<p>1.\u00a0 \u00a0Mediante \u00a0sentencia \u00a0del \u00a031 \u00a0de \u00a0julio \u00a0de \u00a02009, \u00a0el \u00a0Juzgado \u00a01\u00ba \u00a0Penal \u00a0del \u00a0Circuito \u00a0Especializado \u00a0 de \u00a0Villavicencio, \u00a0conden\u00f3, \u00a0entre \u00a0otros, \u00a0a \u00a0RAMIRO \u00a0ALBERTO \u00a0HERN\u00c1NDEZ \u00a0TORRES \u00a0y \u00a0a JOS\u00c9 FREDY SOSA MONTEALEGRE a las penas de 88 meses de \u00a0prisi\u00f3n \u00a0y multa equivalente a 397.22 s.m.l.m.v., por las conductas punibles de \u00a0secuestro \u00a0 simple \u00a0 y \u00a0concierto \u00a0para \u00a0delinquir \u00a0con \u00a0fines \u00a0de \u00a0homicidio \u00a0y \u00a0conformaci\u00f3n de grupos armados ilegales. \u00a0\u00a0<\/p>\n<p>2. \u00a0La \u00a0anterior \u00a0determinaci\u00f3n \u00a0fue \u00a0recurrida \u00a0en apelaci\u00f3n por el defensor del procesado Luis \u00a0Arlex \u00a0Arango \u00a0C\u00e1rdenas \u00a0y \u00a0modificada \u00a0en \u00a0segunda \u00a0instancia \u00a0por el Tribunal \u00a0Superior \u00a0de \u00a0Villavicencio \u00a0el \u00a027 \u00a0de \u00a0febrero de 2012. Se dispuso a favor del \u00a0nombrado \u00a0procesado \u00a0la \u00a0cesaci\u00f3n \u00a0de \u00a0procedimiento por el delito de concierto \u00a0para \u00a0delinquir \u00a0agravado y se procedi\u00f3 a la correspondiente redosificaci\u00f3n de \u00a0la pena a imponer. \u00a0\u00a0<\/p>\n<p>3. \u00a0Ejecutoriado el \u00a0fallo, \u00a0la \u00a0vigilancia \u00a0y \u00a0ejecuci\u00f3n \u00a0de \u00a0las \u00a0sanciones impuestas a HERN\u00c1NDEZ \u00a0TORRES \u00a0y \u00a0a \u00a0SOSA \u00a0MONTEALEGRE estuvo a cargo del Juzgado 15\u00ba de Ejecuci\u00f3n de \u00a0Penas \u00a0y Medidas de Seguridad de Bogot\u00e1 en consideraci\u00f3n a que los mencionados \u00a0condenados \u00a0se \u00a0encentraban \u00a0recluidos \u00a0en \u00a0el \u00a0Establecimiento \u00a0Penitenciario y \u00a0Carcelario \u00a0\u201cLa \u00a0Picota\u201d \u00a0de esta ciudad, por cuenta de un proceso diferente \u00a0\u2013no se especific\u00f3 a cu\u00e1l \u00a0se \u00a0 \u00a0 \u00a0 \u00a0hac\u00eda \u00a0 \u00a0 \u00a0 \u00a0referencia\u2013. \u00a0\u00a0<\/p>\n<p>4. \u00a0Acto \u00a0seguido, \u00a0seg\u00fan \u00a0 \u00a0 lo \u00a0 \u00a0dispuesto \u00a0 \u00a0en \u00a0 \u00a0el \u00a0 \u00a0Acuerdo \u00a0 \u00a0CSBTA \u00a0 \u00a016 \u00a0 \u00a0\u2013 \u00a0472 \u00a0del \u00a021 \u00a0de \u00a0junio \u00a0de 2016, la \u00a0actuaci\u00f3n \u00a0fue \u00a0reasignada \u00a0al \u00a0Juzgado \u00a07\u00ba \u00a0Ejecuci\u00f3n \u00a0de Penas y Medidas de \u00a0Seguridad \u00a0de \u00a0Bogot\u00e1. \u00a0Sin \u00a0embargo, mediante prove\u00eddo del 2 de septiembre de \u00a02016 \u00a0el despacho orden\u00f3 remitir el expediente a su hom\u00f3logo en Villavicencio, \u00a0por \u00a0 \u00a0cuanto \u00a0 \u00a0\u00abde \u00a0 \u00a0la \u00a0 \u00a0revisi\u00f3n \u00a0 de \u00a0 las \u00a0diligencias\u00bb \u00a0asumi\u00f3 \u00a0que \u00a0los condenados estaban en \u00a0libertad \u00a0\u00abcon orden de captura vigente\u00bb. \u00a0\u00a0<\/p>\n<p>As\u00ed, entendi\u00f3 que el funcionario competente \u00a0para \u00a0conocer \u00a0del \u00a0cumplimiento \u00a0de \u00a0la \u00a0sentencia \u00a0condenatoria era el juez de \u00a0ejecuci\u00f3n \u00a0de \u00a0penas \u00a0y \u00a0medidas \u00a0de \u00a0seguridad \u00a0del \u00a0lugar \u00a0donde \u00a0la misma se \u00a0profiri\u00f3, \u00a0para el caso el de Villavicencio.\u00a0 Por ende, dispuso remitir el \u00a0expediente \u00a0al \u00a0Juzgado \u00a01\u00ba \u00a0de \u00a0Ejecuci\u00f3n \u00a0de Penas y Medidas de Seguridad de \u00a0Villavicencio, \u00a0 \u00a0 al \u00a0 \u00a0 que \u00a0 \u00a0 le \u00a0 \u00a0 propuso \u00a0 \u00a0 conflicto \u00a0 \u00a0negativo \u00a0 \u00a0de \u00a0competencias. \u00a0\u00a0<\/p>\n<p>5. Mediante auto del \u00a06 \u00a0de \u00a0octubre \u00a0de \u00a02016 \u00a0el \u00a0Juzgado \u00a01\u00ba \u00a0de \u00a0Ejecuci\u00f3n de Penas y Medidas de \u00a0Seguridad \u00a0de \u00a0Villavicencio, \u00a0se \u00a0abstuvo \u00a0de \u00a0asumir \u00a0el \u00a0conocimiento \u00a0de \u00a0la \u00a0actuaci\u00f3n.\u00a0 \u00a0Precis\u00f3 \u00a0que \u00a0HERN\u00c1NDEZ \u00a0TORRES \u00a0y \u00a0SOSA MONTEALEGRE s\u00ed se \u00a0encuentran \u00a0privados \u00a0de \u00a0la \u00a0libertad \u00a0en esta ciudad, pero no por raz\u00f3n de la \u00a0condena \u00a0que \u00a0les \u00a0impuso \u00a0el \u00a0Juzgado \u00a01\u00ba \u00a0Penal del Circuito Especializado de \u00a0Villavicencio, \u00a0 sino \u00a0 por \u00a0 cuenta \u00a0 de \u00a0 un \u00a0proceso \u00a0diferente \u00a0\u2013sin \u00a0 especificar \u00a0 a \u00a0cu\u00e1l \u00a0hac\u00eda \u00a0referencia\u2013. Por \u00a0consiguiente, \u00a0consider\u00f3 \u00a0que \u00a0carec\u00eda \u00a0de \u00a0competencia \u00a0para \u00a0vigilar el cumplimiento de esa sanci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Dijo expresamente: \u00a0\u00a0<\/p>\n<p>\u00ab(\u2026) \u00a0este Despacho tampoco se considera \u00a0competente \u00a0para \u00a0conocer \u00a0de \u00a0las \u00a0diligencias, \u00a0a\u00fan \u00a0m\u00e1s \u00a0cuando \u00a0la Sala de \u00a0Casaci\u00f3n \u00a0Penal \u00a0de \u00a0la \u00a0Corte \u00a0Suprema \u00a0de Justicia en prove\u00eddo de fecha 3 de \u00a0diciembre \u00a0de \u00a02014 \u00a0dirimi\u00f3 \u00a0una \u00a0colisi\u00f3n \u00a0de \u00a0competencia \u00a0promovida \u00a0en el \u00a0presente \u00a0evento \u00a0pero \u00a0respecto \u00a0del \u00a0condenado \u00a0LUIS \u00a0ARLEX \u00a0ARANGO C\u00c1RDENAS, \u00a0declarando \u00a0o \u00a0asignando \u00a0la \u00a0competencia \u00a0al \u00a0Juzgado 15\u00ba Hom\u00f3logo de aquella \u00a0ciudad (\u2026)\u00bb. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0consecuencia, \u00a0remiti\u00f3 \u00a0el \u00a0expediente a esta Corporaci\u00f3n para \u00a0que \u00a0se \u00a0defina cu\u00e1l de las dos autoridades judiciales es la competente en este \u00a0caso. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE \u00a0LA \u00a0CORTE \u00a0\u00a0<\/p>\n<p>1. \u00a0Al tenor de lo \u00a0normado \u00a0en el art\u00edculo 75-4 de la Ley 600 de 2000, estatuto adjetivo bajo cuya \u00a0\u00e9gida \u00a0se \u00a0adelanta \u00a0el presente proceso, la Sala es competente para desatar la \u00a0colisi\u00f3n \u00a0de \u00a0competencias, \u00a0por \u00a0cuanto \u00a0involucra \u00a0despachos de los distritos \u00a0judiciales de Bogot\u00e1 y Meta. \u00a0\u00a0<\/p>\n<p>2. \u00a0La colisi\u00f3n de \u00a0competencia \u00a0es el mecanismo previsto por el legislador, encaminado a determinar \u00a0qu\u00e9 \u00a0juez \u00a0es \u00a0el facultado para conocer de determinados asuntos, cuando existe \u00a0discusi\u00f3n \u00a0entre \u00a0varios \u00a0funcionarios judiciales, atendiendo a los factores de \u00a0competencia \u00a0y \u00a0al \u00a0principio \u00a0de \u00a0legalidad, que deben observarse en raz\u00f3n del \u00a0debido proceso. \u00a0\u00a0<\/p>\n<p>3. \u00a0 En \u00a0 esta \u00a0oportunidad \u00a0corresponde \u00a0a \u00a0la \u00a0Corporaci\u00f3n establecer a cu\u00e1l de los Juzgados \u00a01\u00ba \u00a0de \u00a0Ejecuci\u00f3n \u00a0de \u00a0Penas \u00a0y \u00a0Medidas \u00a0de \u00a0Seguridad de Villavicencio o 7\u00ba \u00a0Hom\u00f3logo \u00a0de \u00a0Bogot\u00e1, \u00a0le \u00a0corresponde \u00a0vigilar la sentencia impuesta a RAMIRO \u00a0ALBERTO HERN\u00c1NDEZ TORRES y a JOS\u00c9 FREDY SOSA MONTEALEGRE.\u00a0 \u00a0\u00a0<\/p>\n<p>Ello, \u00a0por cuanto el Juzgado de Bogot\u00e1 para \u00a0marginarse \u00a0del \u00a0conocimiento \u00a0del \u00a0asunto, argument\u00f3 que los implicados est\u00e1n \u00a0recluidos \u00a0en \u00a0esta \u00a0ciudad \u00a0por un asunto diferente al que motiv\u00f3 la rese\u00f1ada \u00a0condena, \u00a0 raz\u00f3n \u00a0 por \u00a0 la \u00a0 cual \u00a0 considera \u00a0 que \u00a0 est\u00e1n \u00a0en \u00a0libertad \u00a0por \u00a0este \u00a0proceso \u00a0y por ende, \u00a0debe \u00a0asumir \u00a0el \u00a0conocimiento de la vigilancia de la sanci\u00f3n, el juzgado de la \u00a0misma \u00a0 especialidad \u00a0 en \u00a0 Villavicencio, \u00a0 donde \u00a0se \u00a0profiri\u00f3 \u00a0la \u00a0sentencia \u00a0condenatoria. \u00a0Sin embargo, este \u00faltimo despacho judicial considera que tampoco \u00a0es \u00a0competente, \u00a0toda \u00a0vez \u00a0que \u00a0los condenados s\u00ed se encuentran privados de la \u00a0libertad, \u00a0 en \u00a0esta \u00a0ciudad, \u00a0pero \u00a0por \u00a0raz\u00f3n \u00a0de \u00a0un \u00a0proceso \u00a0diferente \u00a0al \u00a0presente. \u00a0\u00a0<\/p>\n<p>4. \u00a0El \u00a0tema \u00a0bajo \u00a0examen \u00a0ha \u00a0sido \u00a0objeto de varios pronunciamientos por parte de la Sala, en los \u00a0mismos \u00a0t\u00e9rminos \u00a0que ahora se reitera. As\u00ed, para determinar a qu\u00e9 juzgado de \u00a0ejecuci\u00f3n \u00a0corresponde \u00a0la \u00a0competencia en cada caso concreto, debe acudirse al \u00a0art\u00edculo \u00a01\u00ba \u00a0del \u00a0Acuerdo \u00a054 \u00a0de 1994 expedido por el Consejo Superior de la \u00a0Judicatura. \u00a0\u00a0<\/p>\n<p>Los jueces de ejecuci\u00f3n de penas y medidas \u00a0de \u00a0seguridad, \u00a0conocen \u00a0de \u00a0todas las cuestiones relacionadas con la ejecuci\u00f3n \u00a0punitiva \u00a0de \u00a0los \u00a0condenados \u00a0que se encuentren en las c\u00e1rceles del respectivo \u00a0Circuito \u00a0donde \u00a0estuvieren \u00a0radicados, \u00a0sin \u00a0consideraci\u00f3n \u00a0al \u00a0lugar donde se \u00a0hubiere proferido la respectiva sentencia. \u00a0\u00a0<\/p>\n<p>Asimismo conocer\u00e1n del cumplimiento de las \u00a0sentencias \u00a0condenatorias, \u00a0donde \u00a0no se hubiere dispuesto el descuento efectivo \u00a0de \u00a0la \u00a0pena, \u00a0siempre \u00a0y \u00a0cuando \u00a0que el fallo de primera o \u00fanica instancia se \u00a0hubiere proferido en el lugar de su sede. \u00a0\u00a0<\/p>\n<p>Del \u00a0anterior postulado se deriva, en primer \u00a0lugar, \u00a0una regla general seg\u00fan la cual, el factor atributivo de competencia es \u00a0el \u00a0personal, \u00a0referido \u00a0al sentenciado privado de la libertad, en el sentido de \u00a0que \u00a0la \u00a0vigilancia de la sentencia corresponde al despacho con sede en el lugar \u00a0donde \u00a0est\u00e9 \u00a0recluido. \u00a0Si \u00a0este \u00a0\u00faltimo \u00a0cambia, \u00a0por \u00a0traslado \u00a0del interno, \u00a0tambi\u00e9n se desplazar\u00e1 la competencia de los jueces ejecutores. \u00a0\u00a0<\/p>\n<p>De \u00a0otra \u00a0parte, \u00a0del \u00a0segundo \u00a0inciso \u00a0del \u00a0art\u00edculo \u00a0transcrito, \u00a0se \u00a0deduce \u00a0que \u00a0la \u00a0aplicaci\u00f3n \u00a0de \u00a0la \u00a0regla \u00a0general \u00a0rese\u00f1ada, \u00a0est\u00e1 \u00a0condicionada \u00a0a que el sentenciado se encuentre privado de la \u00a0libertad, \u00a0o \u00a0por \u00a0lo \u00a0menos, requerido judicialmente en raz\u00f3n de la actuaci\u00f3n \u00a0respecto \u00a0de \u00a0la \u00a0cual debe definirse la competencia; pues si lo est\u00e1 por causa \u00a0de \u00a0otra actuaci\u00f3n, el conocimiento seguir\u00e1 en cabeza del juzgado ejecutor con \u00a0sede \u00a0 en \u00a0 el \u00a0 lugar \u00a0 en \u00a0 el \u00a0 que \u00a0 se \u00a0 haya \u00a0 proferido \u00a0 la \u00a0providencia \u00a0condenatoria1. \u00a0\u00a0<\/p>\n<p>Ahora, \u00a0en \u00a0particular, sobre el asunto bajo \u00a0examen \u00a0la \u00a0Corte, \u00a0en \u00a0providencia \u00a0CSJ \u00a0AP, 09 Jul 2012, Rad. 39344, precis\u00f3: \u00a0\u00a0<\/p>\n<p>En \u00a0este punto se hace imperioso, entonces, \u00a0precisar \u00a0que \u00a0el \u00a0factor personal que prevalece a la hora de determinar a cu\u00e1l \u00a0funcionario \u00a0de \u00a0ejecuci\u00f3n \u00a0de \u00a0penas \u00a0y \u00a0medidas \u00a0de \u00a0seguridad le corresponde \u00a0vigilar \u00a0la \u00a0sanci\u00f3n, \u00a0supone \u00a0necesariamente \u00a0que \u00a0el \u00a0individuo \u00a0que se halla \u00a0privado \u00a0de la libertad se encuentra en tal condici\u00f3n en virtud de la sentencia \u00a0de \u00a0cuya vigilancia se trata (y no por raz\u00f3n de una situaci\u00f3n distinta, v. gr. \u00a0una \u00a0detenci\u00f3n \u00a0preventiva \u00a0intramural, \u00a0una \u00a0captura \u00a0o \u00a0por \u00a0una \u00a0infracci\u00f3n \u00a0policiva), \u00a0 o \u00a0 bien \u00a0 que \u00a0 est\u00e1 \u00a0 siendo \u00a0judicialmente \u00a0requerido \u00a0para \u00a0su \u00a0cumplimiento. \u00a0\u00a0<\/p>\n<p>Es precisamente por lo anterior que no tiene \u00a0raz\u00f3n \u00a0de ser la remisi\u00f3n de la actuaci\u00f3n, cuya vigilancia realiza el juez de \u00a0ejecuci\u00f3n \u00a0de \u00a0penas \u00a0y medidas de seguridad de Popay\u00e1n, lugar donde [\u2026] fue \u00a0sentenciado, \u00a0sin \u00a0que a la fecha est\u00e9 siendo requerido para el cumplimiento de \u00a0la \u00a0sanci\u00f3n, \u00a0por \u00a0haber \u00a0sido \u00a0beneficiado \u00a0con \u00a0el \u00a0subrogado, con destino al \u00a0despacho \u00a0de su hom\u00f3logo de Pasto, solamente por el hecho de que aquel result\u00f3 \u00a0privado \u00a0de \u00a0la \u00a0libertad \u00a0en \u00a0Tumaco, \u00a0por \u00a0un \u00a0asunto \u00a0distinto. \u00a0El \u00a0factor \u00a0personal \u00a0no tiene ese alcance, pues, como se ha dicho, \u00a0adem\u00e1s \u00a0del \u00a0lugar de reclusi\u00f3n tambi\u00e9n se debe tener en cuenta que el sujeto \u00a0est\u00e9 \u00a0descontando \u00a0la \u00a0pena o est\u00e9 requerido para ese efecto, lo que no ocurre \u00a0en \u00a0este \u00a0caso. (Destaca la Sala). \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Adem\u00e1s, \u00a0trat\u00e1ndose \u00a0del \u00a0mismo \u00a0asunto \u00a0que \u00a0motiva \u00a0el \u00a0presente \u00a0pronunciamiento, \u00a0pero \u00a0que \u00a0fuera dictado en el marco del conflicto negativo de \u00a0competencia \u00a0 que \u00a0 se \u00a0 suscit\u00f3 \u00a0 por \u00a0 \u00abid\u00e9ntico \u00a0motivo\u00bb entre los Juzgados 1\u00ba de Ejecuci\u00f3n de Penas \u00a0y \u00a0Medidas de Seguridad de Villavicencio y 15\u00ba de Ejecuci\u00f3n de Penas y Medidas \u00a0de \u00a0Seguridad \u00a0de Bogot\u00e1, y respecto de la vigilancia de la condena impuesta al \u00a0tambi\u00e9n \u00a0 procesado \u00a0 Lu\u00eds \u00a0Arlex \u00a0Arango \u00a0C\u00e1rdenas, \u00a0esta \u00a0Corporaci\u00f3n \u00a0fue \u00a0enf\u00e1tica en se\u00f1alar: \u00a0\u00a0<\/p>\n<p>Se \u00a0 desprende \u00a0de \u00a0lo \u00a0anterior \u00a0que \u00a0el \u00a0pronunciamiento \u00a0del \u00a0Juzgado \u00a0Quince \u00a0de \u00a0Ejecuci\u00f3n \u00a0de \u00a0Penas \u00a0y \u00a0Medidas \u00a0de \u00a0Seguridad \u00a0de \u00a0Bogot\u00e1 \u00a0se aparta ostensiblemente de los mencionados precedentes \u00a0jurisprudenciales, \u00a0de \u00a0conformidad \u00a0con los cuales la \u00a0competencia \u00a0para \u00a0conocer \u00a0de \u00a0la \u00a0ejecuci\u00f3n \u00a0y \u00a0vigilancia \u00a0de \u00a0las \u00a0penas \u00a0y \u00a0sanciones, \u00a0corresponde al juzgado del lugar en donde se encuentre privado de la \u00a0libertad \u00a0el \u00a0condenado, independientemente de que en otro diferente tambi\u00e9n se \u00a0hubiese emitido el fallo respectivo. \u00a0\u00a0<\/p>\n<p>Es \u00a0decir \u00a0que \u00a0la \u00a0competencia, \u00a0cuando el \u00a0condenado \u00a0se \u00a0halla \u00a0privado \u00a0de la libertad, no depende de la naturaleza de la \u00a0conducta \u00a0punible, \u00a0o \u00a0del territorio donde se cometi\u00f3, o del despacho judicial \u00a0que \u00a0dict\u00f3 \u00a0el \u00a0fallo, \u00a0ni \u00a0por \u00a0el \u00a0n\u00famero \u00a0de condenas, ni cu\u00e1l de ellas se \u00a0encuentra \u00a0descontando el sentenciado, ni de peticiones que se hallen pendientes \u00a0de \u00a0resolver, \u00a0sino \u00a0de un factor personal relativo al \u00a0lugar \u00a0donde \u00a0se \u00a0encuentre descontando la pena y si en ese lugar existe o no un \u00a0juez \u00a0de \u00a0ejecuci\u00f3n \u00a0de penas y medidas de seguridad. \u00a0\u00a0<\/p>\n<p>(\u2026) As\u00ed las cosas, establecido lo que la \u00a0Corte \u00a0ha \u00a0determinado \u00a0frente \u00a0a \u00a0la \u00a0ejecuci\u00f3n de los fallos, poco tiene para \u00a0agregar \u00a0 ahora \u00a0 respecto \u00a0 del \u00a0 caso \u00a0concreto, \u00a0toda \u00a0vez \u00a0que \u00a0el \u00a0condenado \u00a0Lu\u00eds \u00a0Arlex \u00a0Arango \u00a0C\u00e1rdenas \u00a0esta \u00a0privado de la \u00a0libertad \u00a0en \u00a0la \u00a0ciudad \u00a0de Bogot\u00e1, sin que para el efecto influya que sea por \u00a0cuenta \u00a0de \u00a0una \u00a0dependencia \u00a0judicial \u00a0diferente \u00a0al \u00a0Juzgado Primero Penal del \u00a0Circuito Especializado de Villavicencio. \u00a0\u00a0<\/p>\n<p>En \u00a0tales \u00a0condiciones, la competencia para \u00a0conocer \u00a0de \u00a0la \u00a0vigilancia \u00a0de \u00a0sus \u00a0sanciones \u00a0impuestas \u00a0a Lu\u00eds Arlex Arango \u00a0C\u00e1rdenas, \u00a0corresponde \u00a0al \u00a0Juzgado \u00a0Quince de Ejecuci\u00f3n de Penas y Medidas de \u00a0Seguridad \u00a0de \u00a0Bogot\u00e1, \u00a0al \u00a0cual \u00a0se \u00a0le \u00a0asignar\u00e1 \u00a0el \u00a0asunto, \u00a0informando lo \u00a0pertinente a su hom\u00f3logo Primero de Villavicencio. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0De \u00a0esta manera, lo all\u00ed resuelto, aplica tambi\u00e9n para el presente \u00a0asunto. \u00a0Le \u00a0asiste raz\u00f3n al Juzgado de Ejecuci\u00f3n de Penas de Villavicencio en \u00a0repeler \u00a0el \u00a0conocimiento del expediente tras considerar que le corresponde a su \u00a0hom\u00f3logo \u00a0con \u00a0sede \u00a0en \u00a0esta \u00a0ciudad, \u00a0ya \u00a0que \u00a0los sentenciados se encuentran \u00a0privados \u00a0de \u00a0su libertad en esta ciudad capital, independientemente que sea por \u00a0cuenta de otra actuaci\u00f3n penal. \u00a0\u00a0<\/p>\n<p>Por \u00a0tanto, \u00a0surge \u00a0di\u00e1fano que la facultad \u00a0para \u00a0custodiar \u00a0el \u00a0cumplimiento \u00a0de \u00a0la \u00a0condena \u00a0impuesta \u00a0a \u00a0RAMIRO \u00a0ALBERTO \u00a0HERN\u00c1NDEZ \u00a0TORRES \u00a0y\u00a0 \u00a0a \u00a0JOS\u00c9 \u00a0FREDY \u00a0SOSA \u00a0MONTEALEGRE, \u00a0corresponde al \u00a0Juzgado \u00a07\u00ba \u00a0de \u00a0Ejecuci\u00f3n de Penas y Medidas de Seguridad de Bogot\u00e1, a donde \u00a0se remitir\u00e1n inmediatamente las diligencias. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0LA \u00a0CORTE \u00a0SUPREMA \u00a0DE JUSTICIA, SALA DE CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 DECLARAR \u00a0que \u00a0la competencia para vigilar \u00a0las \u00a0sanciones impuestas a RAMIRO ALBERTO HERN\u00c1NDEZ TORRES y a JOS\u00c9 FREDY SOSA \u00a0MONTEALEGRE, \u00a0corresponde \u00a0al \u00a0Juzgado \u00a07\u00ba \u00a0de Ejecuci\u00f3n de Penas y Medidas de \u00a0Seguridad \u00a0de \u00a0Bogot\u00e1, conforme con las motivaciones plasmadas en el cuerpo del \u00a0presente \u00a0 \u00a0 \u00a0 \u00a0 prove\u00eddo. \u00a0 \u00a0 \u00a0 \u00a0 En \u00a0 \u00a0 \u00a0 \u00a0 consecuencia, \u00a0 \u00a0 \u00a0 \u00a0ORDENAR \u00a0 el \u00a0 env\u00edo \u00a0inmediato \u00a0de \u00a0las \u00a0diligencias \u00a0al \u00a0citado \u00a0despacho judicial para que se contin\u00fae con el tr\u00e1mite \u00a0correspondiente. \u00a0\u00a0<\/p>\n<p>2. \u00a0Enviar \u00a0copia del presente auto al Juzgado \u00a01\u00ba \u00a0de \u00a0Ejecuci\u00f3n de Penas y Medidas de Seguridad de Villavicencio, para su informaci\u00f3n. \u00a0\u00a0<\/p>\n<p>3. \u00a0Contra \u00a0esta \u00a0decisi\u00f3n no procede recurso alguno. \u00a0\u00a0<\/p>\n<p>Comun\u00edquese y C\u00famplase. \u00a0<\/p>\n<p>GUSTAVO ENRIQUE MALO FERN\u00c1NDEZ \u00a0<\/p>\n<p>JOS\u00c9 FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>FERNANDO ALBERTO CASTRO CABALLERO \u00a0<\/p>\n<p>EUGENIO FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>LUIS ANTONIO HERN\u00c1NDEZ BARBOSA \u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>PATRICIA SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 \u00a0En \u00a0este \u00a0 \u00a0sentido \u00a0 \u00a0se \u00a0 \u00a0pueden \u00a0 confrontar \u00a0 las \u00a0 providencias \u00a0 CSJ \u00a0 \u00a0 AP, \u00a0 \u00a0 22 \u00a0 \u00a0Nov. \u00a0 1996, \u00a0CSJ \u00a0AP, \u00a009 \u00a0Jul. \u00a02012, \u00a0Rad. \u00a039344, \u00a0CSJ, \u00a0AP, 24 Ago. \u00a02016, \u00a0 \u00a0Rad. \u00a0 \u00a048693, \u00a0 \u00a0CSJ, \u00a0 AP, \u00a0 14 \u00a0Sep. \u00a02016, \u00a0Rad. 48830, entre muchas \u00a0otras. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 PATRICIA SALAZAR CU\u00c9LLAR \u00a0 MAGISTRADA \u00a0PONENTE \u00a0\u00a0 AP7606-2016 \u00a0\u00a0 Radicaci\u00f3n \u00a0 \u00a0No.: \u00a049116 \u00a0\u00a0 Acta \u00a0 \u00a0 \u00a0No. \u00a0346 \u00a0\u00a0 Bogot\u00e1 \u00a0D. C.,\u00a0 dos (2) de noviembre de \u00a0dos mil diecis\u00e9is (2016). \u00a0\u00a0 VISTOS \u00a0 De conformidad con lo previsto en el art\u00edculo \u00a075, \u00a0numeral 4\u00b0 de la Ley 600 de 2000, la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-33861","post","type-post","status-publish","format-standard","hentry","category-25"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/33861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=33861"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/33861\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=33861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=33861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=33861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}