{"id":33680,"date":"2023-09-13T19:42:14","date_gmt":"2023-09-13T19:42:14","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap6589-201648425\/"},"modified":"2023-09-13T19:42:14","modified_gmt":"2023-09-13T19:42:14","slug":"ap6589-201648425","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap6589-201648425\/","title":{"rendered":"AP6589-2016(48425)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Eyder Pati\u00f1o Cabrera \u00a0<\/p>\n<p>Magistrado \u00a0ponente \u00a0\u00a0<\/p>\n<p>AP6589-2016 \u00a0<\/p>\n<p>Radicaci\u00f3n N\u00b0 48425 \u00a0<\/p>\n<p>(Aprobado acta N\u00b0 305) \u00a0<\/p>\n<p>Bogot\u00e1, D. C., veintiocho (28) de septiembre \u00a0de dos mil diecis\u00e9is (2016) \u00a0\u00a0<\/p>\n<p>MOTIVO DE LA DECISI\u00d3N \u00a0<\/p>\n<p>Se pronuncia la Sala sobre la admisibilidad \u00a0de \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0por \u00a0el \u00a0apoderado \u00a0de \u00a0Jos\u00e9 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Santos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Castillo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Prieto\u00a0 \u00a0en \u00a0contra \u00a0de \u00a0la sentencia del \u00a019 \u00a0 de \u00a0 febrero \u00a0de \u00a02015, \u00a0mediante \u00a0la cual el \u00a0Tribunal \u00a0 \u00a0Superior \u00a0 \u00a0de \u00a0 Bucaramanga \u00a0revoc\u00f3 parcialmente el fallo condenatorio emitido por el Juzgado \u00a0Segundo Penal del Circuito \u00a0de \u00a0 Depuraci\u00f3n \u00a0de \u00a0esa \u00a0ciudad \u00a0y \u00a0conden\u00f3 \u00a0al \u00a0procesado \u00a0por \u00a0el delito de \u00a0estafa. \u00a0\u00a0<\/p>\n<p>HECHOS Y ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. El \u00a0Ad quem los \u00a0resumi\u00f3 as\u00ed: \u00a0 \u00a0\u00a0<\/p>\n<p>\u00abSe extrae de las \u00a0diligencias \u00a0que \u00a0mediante \u00a0promesa \u00a0de compraventa celebrada el 25 de \u00a0 agosto \u00a0de \u00a02004, \u00a0el \u00a0se\u00f1or \u00a0JOSE \u00a0SANTOS \u00a0CASTILLO \u00a0PRIETO, \u00a0transfiri\u00f3 \u00a0a \u00a0Eduardo \u00a0Rodr\u00edguez \u00a0Quiroga, el veh\u00edculo automotor tipo tracto \u00a0mula \u00a0(sic), \u00a0marca \u00a0Kenworth, \u00a0modelo \u00a01992, por valor de $125.000.000 millones \u00a0de \u00a0pesos; \u00a0sin \u00a0embargo, \u00a0en \u00a0esa fecha el comprador \u00a0ofreci\u00f3 \u00a0el \u00a0monto \u00a0de $110.000.000 millones de pesos, dinero que fue cancelado \u00a0en \u00a0 \u00a0 la \u00a0 \u00a0forma \u00a0 \u00a0estipulada \u00a0 \u00a0en \u00a0 \u00a0el \u00a0 \u00a0referido \u00a0 \u00a0contrato. \u00a0\u00a0<\/p>\n<p>Posteriormente, al ser la v\u00edctima, Eduardo \u00a0Rodr\u00edguez \u00a0del hurto de su automotor, realiz\u00f3 las diligencias pertinentes ante \u00a0la \u00a0aseguradora \u00a0Colseguros; \u00a0no obstante, esta entidad no desembols\u00f3 el dinero \u00a0a \u00a0 \u00a0 \u00a0causa \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0vicios \u00a0 \u00a0 existentes \u00a0en \u00a0los \u00a0documentos \u00a0que \u00a0soportan \u00a0la importaci\u00f3n del \u00a0tracto \u00a0cami\u00f3n \u00a0(sic), \u00a0de los que se logr\u00f3 establecer hab\u00eda sido falsificado \u00a0el \u00a0Manifiesto \u00a0de \u00a0Importaci\u00f3n \u00a0n\u00famero \u00a0011479, la \u00a0carta \u00a0 de \u00a0 la \u00a0DIAN \u00a0del \u00a01 \u00a0de \u00a0octubre \u00a0de \u00a02004, \u00a0en \u00a0el \u00a0que \u00a0(sic) \u00a0 \u00a0falsificaron \u00a0 \u00a0su \u00a0 r\u00fabrica \u00a0solicitando \u00a0 una \u00a0 constancia \u00a0 de \u00a0 tr\u00e1nsito \u00a0del \u00a0Magdalena.\u00bb1 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. Por los \u00a0anteriores \u00a0 \u00a0 hechos \u00a0 \u00a0la \u00a0 \u00a0Fiscal\u00eda \u00a0 \u00a0orden\u00f3 \u00a0apertura \u00a0formal de la instrucci\u00f3n el 23 \u00a0 \u00a0de \u00a0 \u00a0octubre \u00a0 de \u00a0 20092 \u00a0y \u00a0vincul\u00f3 \u00a0al procesado \u00a0 mediante \u00a0 indagatoria \u00a0 el \u00a030 \u00a0 de \u00a0 agosto \u00a0 de \u00a020103. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. El 08 de \u00a0julio \u00a0de 2011 la Fiscal\u00eda \u00a011 Delegada ante los Jueces \u00a0Penales \u00a0 \u00a0 del \u00a0 \u00a0 Circuito \u00a0 \u00a0de \u00a0 \u00a0Bucaramanga \u00a0 \u00a0 \u00a0 \u00a0 \u00a0decret\u00f3 \u00a0 \u00a0 el \u00a0 \u00a0cierre \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0investigaci\u00f3n4 \u00a0 y \u00a0 el \u00a021 \u00a0de \u00a0agosto \u00a0 siguiente \u00a0calific\u00f3 \u00a0el \u00a0m\u00e9rito \u00a0de \u00a0la \u00a0investigaci\u00f3n \u00a0con resoluci\u00f3n de acusaci\u00f3n en \u00a0contra \u00a0de \u00a0Jos\u00e9 \u00a0Santos \u00a0Castillo Prieto, \u00a0 \u00a0 como \u00a0 \u00a0probable \u00a0 \u00a0autor \u00a0 \u00a0del \u00a0delito \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 estafa5.\u00a0 \u00a0Decisi\u00f3n que qued\u00f3 ejecutoriada \u00a0el \u00a0 \u00a0 \u00a002 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 noviembre \u00a0 \u00a0 de \u00a0 \u00a0 20116. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. Una vez \u00a0celebradas \u00a0 \u00a0 las \u00a0 \u00a0 audiencias \u00a0 \u00a0preparatoria7 \u00a0 \u00a0y \u00a0 p\u00fablica8, \u00a0el \u00a024 \u00a0de \u00a0septiembre \u00a0de \u00a02014 \u00a0el \u00a0Juzgado \u00a0 \u00a0 Segundo \u00a0 \u00a0 Penal \u00a0 \u00a0 del \u00a0 \u00a0Circuito \u00a0 \u00a0Adjunto \u00a0 \u00a0de \u00a0Bucaramanga \u00a0 dict\u00f3 \u00a0sentencia \u00a0mediante \u00a0la \u00a0cual \u00a0conden\u00f3 \u00a0a \u00a0Jos\u00e9 \u00a0Santos Castillo Prieto \u00a0a \u00a0la \u00a0pena \u00a0de \u00a0treinta \u00a0(30) meses \u00a0de \u00a0prisi\u00f3n, \u00a0multa \u00a0de \u00a0sesenta \u00a0 (60) \u00a0 salarios \u00a0 m\u00ednimos \u00a0 legales \u00a0 mensuales \u00a0vigentes \u00a0y \u00a0la \u00a0accesoria de interdicci\u00f3n de \u00a0derechos \u00a0 y \u00a0 funciones \u00a0 p\u00fablicas \u00a0 por \u00a0 un \u00a0 t\u00e9rmino \u00a0 igual \u00a0 a \u00a0la \u00a0pena \u00a0principal, como autor del \u00a0delito de estafa. \u00a0 \u00a0\u00a0<\/p>\n<p>Neg\u00f3 el pago de da\u00f1os y perjuicios \u00a0y \u00a0otorg\u00f3 \u00a0la \u00a0suspensi\u00f3n \u00a0condicional \u00a0de \u00a0la \u00a0pena9.\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. El \u00a019 \u00a0 de \u00a0 febrero \u00a0 de \u00a0 2916, \u00a0 el \u00a0 Tribunal \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Superior \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Bucaramanga, \u00a0al conocer del recurso de \u00a0apelaci\u00f3n \u00a0 incoado \u00a0por \u00a0la \u00a0defensa \u00a0y \u00a0la \u00a0parte \u00a0civil, \u00a0 \u00a0 revoc\u00f3 \u00a0 \u00a0parcialmente \u00a0 \u00a0el \u00a0 \u00a0fallo \u00a0recurrido \u00a0 en \u00a0 el \u00a0 numeral \u00a0 tercero, \u00a0conden\u00f3 al procesado a cancelar la \u00a0suma \u00a0 de \u00a0 $128.706.689 \u00a0 millones \u00a0 de \u00a0 pesos \u00a0 a \u00a0 favor \u00a0 de \u00a0 Eduardo \u00a0 \u00a0 \u00a0Rodr\u00edguez \u00a0 \u00a0 Quiroga \u00a0por \u00a0concepto de da\u00f1os y \u00a0perjuicios \u00a0materiales \u00a0y \u00a0confirm\u00f3 \u00a0en \u00a0lo \u00a0dem\u00e1s \u00a0la \u00a0sentencia \u00a0recurrida10.\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>El \u00a0defensor \u00a0del \u00a0procesado, identifica los \u00a0hechos, \u00a0la actuaci\u00f3n y la sentencia impugnada, no as\u00ed los sujetos procesales, \u00a0ni \u00a0tampoco \u00a0se pronuncia sobre la procedencia del recurso y pese a que se\u00f1al\u00f3 \u00a0el \u00a0amparo \u00a0de \u00a0una \u00a0causal \u00fanica, lo cierto es que formula cuatro cargos, tres \u00a0bajo \u00a0la \u00a0causal \u00a0primera \u00a0y \u00a0el \u00a0\u00faltimo \u00a0con \u00a0estribo \u00a0en \u00a0la \u00a0tercera, \u00a0as\u00ed: \u00a0\u00a0<\/p>\n<p>Causal Primera \u00a0<\/p>\n<p>Acusa \u00a0 \u00a0a \u00a0 \u00a0la \u00a0 \u00a0sentencia \u00a0 \u00a0del \u00a0Tribunal \u00a0 \u00a0\u00aben \u00a0 la \u00a0modalidad \u00a0de \u00a0violaci\u00f3n de la norma sustancial proveniente de error de hecho o \u00a0de \u00a0 \u00a0 derecho \u00a0 \u00a0 en \u00a0 \u00a0 la \u00a0 \u00a0 apreciaci\u00f3n \u00a0 \u00a0 de \u00a0 \u00a0la \u00a0 \u00a0prueba\u00bb, \u00a0 \u00a0de \u00a0incurrir \u00a0en \u00abm\u00faltiples \u00a0errores \u00a0de \u00a0la \u00a0valoraci\u00f3n \u00a0(sic) \u00a0probatoria \u00a0por \u00a0darle \u00a0el \u00a0valor que no le \u00a0corresponde \u00a0y \u00a0desconocerle a otras su valor correspondiente\u00bb, \u00abviolaci\u00f3n de \u00a0las \u00a0 pruebas\u00bb \u00a0 que \u00a0lo \u00a0condujeron \u00a0 \u00a0 a \u00a0 \u00a0 condenar \u00a0 \u00a0al \u00a0 \u00a0procesado11. \u00a0\u00a0<\/p>\n<p>Cita \u00a0como \u00a0normas vulneradas los art\u00edculos \u00a0232, \u00a0238 del C\u00f3digo de Procedimiento Penal (Ley 600 de 2000), 6, 22 y 32 de la \u00a0Ley 955 de 2000 y 7 de la Ley 906 de 2004. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. Manifiesta \u00a0que el Tribunal incurri\u00f3 \u00a0 \u00a0 \u00a0 en \u00a0 \u00a0 \u00a0\u00abviolaci\u00f3n \u00a0 indirecta \u00a0de \u00a0la \u00a0ley \u00a0sustancial \u00a0por \u00a0error \u00a0de \u00a0derecho, por falso juicio de identidad\u00bb, \u00a0respecto a la indagatoria rendida por \u00a0el \u00a0procesado el 30 de agosto de 2010 y su ampliaci\u00f3n en audiencia p\u00fablica del \u00a027 \u00a0de \u00a0septiembre \u00a0de \u00a02012, al considerar que no constituye una contradicci\u00f3n \u00a0que \u00a0en \u00a0la \u00a0primera \u00a0salida manifestara conocer a la v\u00edctima, y posteriormente \u00a0se\u00f1alara \u00a0 \u00a0 lo \u00a0 \u00a0 contrario, \u00a0 \u00a0 \u00abpor \u00a0cuanto \u00a0lo \u00a0dicho en la audiencia inicial, en primer lugar la \u00a0respuesta \u00a0no, \u00a0expresa \u00a0(sic) \u00a0c\u00f3mo \u00a0y en donde y porque (sic) conoci\u00f3 al sr. \u00a0CASTILLO \u00a0PRIETO al Sr. EDUARDO RODRIGUEZ QUIROGA, en segundo lugar, la pregunta \u00a0no \u00a0espec\u00edfica \u00a0que \u00a0tipo \u00a0de \u00a0conocimiento \u00a0se refiere, si de vista, trato y\/o \u00a0comunicaci\u00f3n, \u00a0en \u00a0tercer \u00a0lugar \u00a0no \u00a0recuerda \u00a0el \u00a0Sr. \u00a0SANTOS \u00a0CASTILLO, como \u00a0entendi\u00f3 \u00a0 la \u00a0 pregunta \u00a0 en \u00a0el \u00a0momento \u00a0que \u00a0se \u00a0la \u00a0formularon\u00bb. \u00a0 \u00a0\u00a0<\/p>\n<p>Afirma \u00a0 \u00a0 que \u00a0 \u00a0 se \u00a0 \u00a0 \u00abdistorsion\u00f3 \u00a0 el \u00a0 sentido \u00a0de \u00a0la \u00a0injurada\u00bb \u00a0inicial, en el \u00a0punto \u00a0donde \u00a0el \u00a0acusado \u00a0asegur\u00f3 \u00a0que Medardo \u00a0 \u00a0 \u00a0 Mera \u00a0 \u00a0 \u00a0fue \u00a0la \u00a0persona \u00a0que \u00a0realiz\u00f3 \u00a0los \u00a0tr\u00e1mites \u00a0pertinentes para el \u00a0traspaso \u00a0del \u00a0veh\u00edculo, \u00a0frente \u00a0a lo sostenido en su ampliaci\u00f3n en audiencia \u00a0p\u00fablica, \u00a0en \u00a0la \u00a0que \u00a0refiri\u00f3 \u00a0que \u00a0fue \u00a0un intermediario en la negociaci\u00f3n, \u00a0debido \u00a0a \u00a0que el vendedor Luis Mu\u00f1oz no pose\u00eda c\u00e9dula colombiana y que nunca \u00a0ostent\u00f3 \u00a0 la \u00a0calidad \u00a0de \u00a0poseedor \u00a0del \u00a0automotor \u00a0como \u00a0se \u00a0registra \u00a0en \u00a0el \u00a0\u00abcertificado \u00a0 \u00a0de \u00a0tradici\u00f3n y libertad\u00bb (sic). \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. Postula un error de derecho porque \u00a0el \u00a0Ad \u00a0quem, \u00abal \u00a0sopesar \u00a0o valorar la prueba\u00bb no \u00a0confiri\u00f3 \u00a0\u00abel valor probatorio del indubio pro reo \u00a0(sic)\u00bb con respecto al manifiesto de importaci\u00f3n, en \u00a0atenci\u00f3n \u00a0 \u00a0a \u00a0 que \u00a0 no \u00a0 existe \u00a0 \u00abconstancia \u00a0de \u00a0que \u00a0el \u00a0procesado haya firmado la declaraci\u00f3n de \u00a0este \u00a0documento\u00bb. \u00a0Esta \u00a0situaci\u00f3n, \u00a0unida a que los \u00a0pagos \u00a0se registraron a nombre de otra persona, llevan a concluir que el acusado \u00a0no \u00a0fue \u00a0quien \u00a0falsific\u00f3 el documento referido, por lo cual se debi\u00f3 declarar \u00a0la duda a favor de \u00e9ste. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. M\u00e1s adelante, sin guardar un orden, \u00a0en \u00a0el \u00a0cap\u00edtulo \u00a0quinto, \u00a0plantea otro \u00a0reparo a la sentencia a la luz del numeral primero del art\u00edculo \u00a0207, \u00a0 \u00a0por \u00a0 \u00a0estimar \u00a0 \u00a0que \u00a0 \u00a0el \u00a0 \u00a0Tribunal \u00a0 \u00a0incurri\u00f3 \u00a0 en \u00a0 \u00abun \u00a0 error \u00a0de \u00a0derecho\u00bb \u00a0 \u00a0al \u00a0 \u00a0valorar \u00a0 \u00a0\u00aberr\u00f3neamente \u00a0la \u00a0prueba documental \u00a0del \u00a0 \u00a0 contrato \u00a0 \u00a0de \u00a0 \u00a0rescisi\u00f3n\u00bb. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 \u00a0<\/p>\n<p>Al \u00a0respecto \u00a0manifiesta que la rescisi\u00f3n \u00a0del \u00a0acuerdo inicial y su \u00a0posterior \u00a0incumplimiento \u00a0tan \u00a0solo constituye una infracci\u00f3n contractual y no \u00a0tiene \u00a0 el \u00a0 valor \u00a0de \u00a0comprometer \u00a0la \u00a0responsabilidad \u00a0penal \u00a0del \u00a0encausado. \u00a0Seg\u00fan \u00a0se \u00a0logra entender, frente a ese \u00a0 \u00a0 \u00a0 \u00a0 \u00a0acto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0posterior \u00a0 \u00a0 \u00a0 \u00a0 \u00a0al \u00a0 \u00a0 \u00a0 \u00a0 contrato \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00abno podremos hablar de contrato civil \u00a0criminalizado \u00a0 \u00a0 \u00a0 \u00a0sino \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 incumplimiento \u00a0 \u00a0 \u00a0 civil\u00bb. \u00a0\u00a0<\/p>\n<p>Concluye \u00a0 que \u00a0 de \u00a0 haberse \u00a0valorado \u00a0esta \u00a0prueba \u00a0apropiadamente, \u00a0al cesar los efectos \u00a0del \u00a0contrato \u00a0principal \u00a0por \u00a0las \u00a0partes, \u00a0una \u00a0vez se incumple la rescisi\u00f3n, el camino a seguir era la \u00a0acci\u00f3n civil de resoluci\u00f3n contractual. \u00a0\u00a0<\/p>\n<p>Causal Tercera \u00a0<\/p>\n<p>Se\u00f1ala \u00a0que \u00a0el \u00a0Tribunal \u00a0no \u00a0consider\u00f3 \u00a0\u00abla \u00a0falta de investigaci\u00f3n integral\u00bb \u00a0 por \u00a0parte \u00a0de \u00a0la \u00a0Fiscal\u00eda, \u00a0en \u00a0su \u00a0criterio, \u00a0porque \u00a0no \u00a0se \u00a0identific\u00f3 \u00a0a \u00a0Medardo \u00a0Enrique Berdugo Castro, Eduardo Mera -a nombre de quien \u00a0figuraban \u00a0los \u00a0pagos- \u00a0y Luis Mu\u00f1oz -propietario del automotor-, referidos por \u00a0el \u00a0 \u00a0procesado \u00a0 \u00a0y \u00a0 \u00a0por \u00a0 \u00a0no \u00a0 \u00a0realizarse \u00a0 las \u00a0 preguntas \u00a0 \u00abnecesarias \u00a0 \u00a0 y \u00a0 \u00a0 suficientes\u00bb \u00a0para \u00a0determinar \u00a0\u00abtodo lo \u00a0relacionado \u00a0 con \u00a0 el \u00a0contrato \u00a0de \u00a0compraventa\u00bb. \u00a0Cita \u00a0 como \u00a0normas \u00a0presuntamente \u00a0trasgredidas \u00a0los \u00a0art\u00edculos \u00a020 \u00a0del \u00a0C.P.C. \u00a0(sic), \u00a0alusivo \u00a0a la investigaci\u00f3n integral y 16, referente a la finalidad del \u00a0procedimiento. \u00a0\u00a0<\/p>\n<p>Insiste \u00a0 en \u00a0 que \u00a0 no \u00a0se \u00a0realiz\u00f3 \u00a0una \u00a0investigaci\u00f3n \u00a0integral \u00a0en \u00a0la instrucci\u00f3n, que su poderdante es \u00abuna \u00a0persona \u00a0altamente ocupada\u00bb y que \u00a0s\u00ed \u00a0se \u00abhubiera investigado m\u00e1s sobre la conducta, \u00a0y \u00a0 las \u00a0 circunstancias \u00a0 en \u00a0 las \u00a0que \u00a0actu\u00f3\u00bb \u00a0la \u00a0conclusi\u00f3n \u00a0del \u00a0A \u00a0quo no \u00a0pod\u00eda ser condena. \u00a0\u00a0<\/p>\n<p>Finalmente, \u00a0 \u00a0 \u00a0 postula \u00a0 \u00a0 \u00a0 un \u00a0 \u00a0 \u00a0 apartado \u00a0 \u00a0 \u00a0 denominado \u00a0 \u00a0 \u00a0\u00abcasaci\u00f3n \u00a0 \u00a0oficiosa\u00bb,\u00a0 \u00a0amparado \u00a0en el art\u00edculo 214 de la Ley 600 de 2000, \u00a0en \u00a0el \u00a0que \u00a0afirma \u00a0que \u00a0la \u00a0Corte debe declarar de \u00a0\u00aboficio \u00a0la \u00a0causal \u00a0tercera \u00a0del art\u00edculo 220 del \u00a0mismo \u00a0 ordenamiento\u00bb, \u00a0cuando \u00a0sea \u00a0ostensible \u00a0que \u00a0se atente contra las garant\u00edas fundamentales o se \u00a0\u00abreconozca la existencia \u00a0de \u00a0 \u00a0un \u00a0 \u00a0derecho \u00a0 \u00a0fundamental \u00a0 \u00a0merecedor \u00a0 \u00a0de \u00a0 \u00a0proyecci\u00f3n\u00bb \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (sic). \u00a0\u00a0<\/p>\n<p>Por \u00a0todo \u00a0lo expuesto pide casar el fallo y \u00a0que \u00a0 su \u00a0defendido \u00a0sea \u00a0absuelto \u00a0de \u00a0los \u00a0cargos. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. La \u00a0Sala \u00a0inadmitir\u00e1 la demanda que se examina porque no re\u00fane las \u00a0exigencias previstas en la ley, como pasa a verse. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La \u00a0posibilidad \u00a0de acudir a esta sede extraordinaria, comporta para \u00a0el \u00a0memorialista \u00a0la \u00a0obligaci\u00f3n de presentar una demanda en la que acredite el \u00a0cumplimiento \u00a0de \u00a0los requisitos de \u00edndole formal y sustancial prescritos en la \u00a0ley. \u00a0 \u00a0\u00a0<\/p>\n<p>Adem\u00e1s \u00a0de los presupuestos concernientes a \u00a0la \u00a0identificaci\u00f3n \u00a0de \u00a0los \u00a0sujetos \u00a0procesales, \u00a0la \u00a0sentencia recurrida, los \u00a0hechos \u00a0y \u00a0la \u00a0actuaci\u00f3n, el art\u00edculo 212 de la Ley 600 de 2000 consagra en el \u00a0numeral \u00a03\u00ba, \u00a0la \u00a0obligaci\u00f3n \u00a0de \u00a0enunciar \u00a0la \u00a0causal \u00a0y formular el cargo, e \u00a0indicar \u00a0en \u00a0forma \u00a0clara \u00a0y precisa los fundamentos que le asisten y las normas \u00a0que \u00a0estima \u00a0conculcadas, \u00a0as\u00ed como las fallas atribuibles al sentenciador y el \u00a0da\u00f1o \u00a0 \u00a0 \u00a0 producido \u00a0 \u00a0 \u00a0por \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0decisi\u00f3n \u00a0 \u00a0 \u00a0recurrida. \u00a0\u00a0<\/p>\n<p>En orden a desvirtuar la doble presunci\u00f3n de \u00a0acierto \u00a0y \u00a0legalidad que recae sobre el fallo de segundo grado, la petici\u00f3n de \u00a0casaci\u00f3n \u00a0debe \u00a0ser elaborada por quien demuestre tener inter\u00e9s jur\u00eddico para \u00a0impugnar, \u00a0respetando, al efecto, las formalidades t\u00e9cnico jur\u00eddicas previstas \u00a0en la ley y la jurisprudencia. \u00a0\u00a0<\/p>\n<p>En ese sentido, la demanda debe ser \u00edntegra \u00a0en \u00a0su formulaci\u00f3n, suficiente, clara y precisa en su desarrollo y eficaz en la \u00a0pretensi\u00f3n, \u00a0de \u00a0tal suerte que se debe soportar en los principios que rigen el \u00a0recurso, \u00a0en \u00a0especial, los de claridad, precisi\u00f3n, fundamentaci\u00f3n, prioridad, \u00a0no \u00a0contradicci\u00f3n \u00a0y \u00a0autonom\u00eda, \u00a0sin que sea viable argumentar a manera de un \u00a0alegato de instancia. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. Conforme \u00a0lo previsto en el inciso 1\u00ba del art\u00edculo 205 del C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0de \u00a02000, el recurso extraordinario procede contra las \u00a0sentencias \u00a0proferidas \u00a0en \u00a0segunda \u00a0instancia \u00a0por los Tribunales Superiores de \u00a0Distrito \u00a0Judicial, \u00a0cuando \u00a0se \u00a0trate \u00a0de \u00a0delitos \u00a0que \u00a0tengan \u00a0se\u00f1alada pena \u00a0privativa \u00a0de \u00a0la \u00a0libertad \u00a0cuyo \u00a0m\u00e1ximo exceda de ocho (8) a\u00f1os, pero, de no \u00a0cumplir \u00a0el \u00a0fallo \u00a0con \u00a0los presupuestos descritos, el legislador facult\u00f3 a la \u00a0Corte \u00a0para que, de manera excepcional, admita las demandas que se ajusten a los \u00a0requisitos \u00a0legales, siempre que lo considere necesario para el desarrollo de la \u00a0jurisprudencia o para garantizar derechos fundamentales. \u00a0 \u00a0\u00a0<\/p>\n<p>Por \u00a0tanto, acorde con las normas aplicables \u00a0al \u00a0caso \u00a0concreto, \u00a0debe \u00a0advertirse \u00a0en primer lugar que la conducta de estafa \u00a0tiene \u00a0prevista una pena de dos (02) a ocho (08) a\u00f1os de prisi\u00f3n, supuesto que \u00a0determina \u00a0 la \u00a0 improcedencia \u00a0 de \u00a0 la \u00a0 casaci\u00f3n \u00a0 ordinaria \u00a0 en \u00a0 el \u00a0caso \u00a0concreto. \u00a0\u00a0<\/p>\n<p>Siendo \u00a0lo anterior as\u00ed, es evidente que el \u00a0demandante \u00a0estaba \u00a0obligado \u00a0a acreditar la necesidad de avocar el conocimiento \u00a0del \u00a0 \u00a0asunto \u00a0 \u00a0excepcionalmente \u00a0 \u00a0\u00abpara \u00a0el \u00a0desarrollo \u00a0de \u00a0la \u00a0jurisprudencia o la garant\u00eda de los \u00a0derechos \u00a0fundamentales\u00bb; \u00a0sin \u00a0embargo \u00a0lo \u00a0omiti\u00f3, al punto que al final de su escrito con fundamento en \u00a0el \u00a0art\u00edculo \u00a0214 \u00a0de \u00a0la \u00a0Ley \u00a0600 de 2000, declarado inexequible por la Corte \u00a0Constitucional, \u00a0 \u00a0 anunci\u00f3 \u00a0 \u00a0 un \u00a0 \u00a0 apartado \u00a0 \u00a0 denominado \u00a0 \u00a0 \u00abcasaci\u00f3n \u00a0 oficiosa\u00bb, sin ninguna sustentaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. Adicionalmente, \u00a0 \u00a0 \u00a0 \u00a0los \u00a0cargos \u00a0propuestos \u00a0tampoco superan el juicio l\u00f3gico jur\u00eddico \u00a0de \u00a0 \u00a0 admisi\u00f3n. \u00a0 \u00a0 Las \u00a0 \u00a0 siguientes \u00a0 \u00a0 son \u00a0 \u00a0 las \u00a0 \u00a0razones:\u00a0\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Se\u00f1ala, \u00a0con \u00a0base \u00a0en \u00a0la \u00a0causal \u00a0primera \u00a0 del \u00a0 art\u00edculo \u00a0 207 \u00a0 de \u00a0 la \u00a0 Ley \u00a0600 \u00a0 de \u00a0 2000, \u00a0 la \u00a0violaci\u00f3n \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0normas \u00a0 \u00a0 \u00a0sustanciales \u00a0derivada de \u00abun error de \u00a0hecho \u00a0 \u00a0 o \u00a0 \u00a0 de \u00a0 \u00a0 derecho \u00a0 \u00a0en \u00a0 \u00a0la \u00a0 \u00a0apreciaci\u00f3n \u00a0 \u00a0de \u00a0 \u00a0determinada \u00a0 \u00a0prueba\u00bb. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 En \u00a0 \u00a0 su \u00a0 \u00a0 concepto, \u00a0 \u00a0la \u00a0 sentencia \u00a0 del \u00a0 Tribunal \u00a0incurre \u00a0en \u00abun \u00a0error \u00a0de \u00a0derecho, \u00a0por \u00a0falso \u00a0juicio \u00a0 de \u00a0identidad\u00bb \u00a0por \u00a0 \u00a0 distorsi\u00f3n \u00a0de \u00a0la \u00a0injurada \u00a0y \u00a0su \u00a0amplicaci\u00f3n, con lo cual \u00a0queda \u00a0 \u00a0expuesta \u00a0 \u00a0la \u00a0 confusi\u00f3n \u00a0 frente \u00a0 a \u00a0 la \u00a0 causal \u00a0 de \u00a0 casaci\u00f3n \u00a0invocada. \u00a0 \u00a0\u00a0<\/p>\n<p>Se precisa que \u00a0la \u00a0 violaci\u00f3n \u00a0 de \u00a0 la \u00a0 ley \u00a0 bajo \u00a0 la \u00a0 causal \u00a0primera \u00a0del \u00a0precepto \u00a0 \u00a0 207 \u00a0 \u00a0 del \u00a0C\u00f3digo \u00a0de \u00a0 \u00a0 \u00a0Procedimiento \u00a0 \u00a0 Penal, \u00a0 \u00a0 comprende \u00a0dos \u00a0supuestos \u00a0que \u00a0pueden \u00a0proponerse \u00a0 \u00a0 \u00a0 \u00a0 bajo \u00a0 \u00a0 \u00a0 \u00a0 la \u00a0censura \u00a0de \u00a0infracci\u00f3n \u00a0directa o indirecta. \u00a0\u00a0<\/p>\n<p>En \u00a0la primera hip\u00f3tesis, el actor tiene el \u00a0imperativo \u00a0de se\u00f1alar las disposiciones sustanciales objeto de transgresi\u00f3n y \u00a0el \u00a0sentido \u00a0de \u00a0vulneraci\u00f3n, \u00a0esto \u00a0es, \u00a0si \u00a0lo \u00a0fue por falta de aplicaci\u00f3n, \u00a0indebida aplicaci\u00f3n o interpretaci\u00f3n err\u00f3nea. \u00a0\u00a0<\/p>\n<p>Por su parte, si el reclamo se postula por la \u00a0segunda \u00a0 opci\u00f3n, \u00a0 la \u00a0 inconformidad \u00a0debe \u00a0manifestarse \u00a0a \u00a0trav\u00e9s \u00a0de \u00a0los \u00a0denominados \u00a0errores \u00a0de hecho o de derecho. El error \u00a0de \u00a0hecho \u00a0ese \u00a0manifiesta \u00a0mediante \u00a0los \u00a0juicios \u00a0de \u00a0existencia, \u00a0identidad \u00a0y el falso raciocinio y busca se\u00f1alar el yerro judicial \u00a0en \u00a0la contemplaci\u00f3n de la prueba. En tanto el error \u00a0de \u00a0derecho, se configura como consecuencia de un falso \u00a0juicio \u00a0de \u00a0legalidad \u00a0o \u00a0uno \u00a0de \u00a0convicci\u00f3n, \u00a0relacionados, el primero con la \u00a0regulaci\u00f3n \u00a0del \u00a0proceso de producci\u00f3n y aducci\u00f3n de la prueba, y el segundo, \u00a0con \u00a0el \u00a0desconocimiento de la tarifa legal de la misma, asignada en determinado \u00a0precepto. \u00a0\u00a0<\/p>\n<p>En ambos eventos, con la carga de justificar \u00a0la \u00a0trascendencia \u00a0en la \u00a0decisi\u00f3n \u00a0y \u00a0la \u00a0necesidad \u00a0de \u00a0atender \u00a0uno \u00a0de \u00a0los \u00a0fines \u00a0fijados \u00a0para \u00a0el \u00a0efecto. \u00a0\u00a0<\/p>\n<p>Como \u00a0queda expuesto, cada esquema supone un \u00a0orden \u00a0met\u00f3dico \u00a0y \u00a0estructurado \u00a0a \u00a0efectos \u00a0de \u00a0formular un alegato que logre \u00a0confrontar \u00a0los \u00a0fundamentos \u00a0de \u00a0las \u00a0decisiones \u00a0de \u00a0instancia, \u00a0con el fin de \u00a0acreditar \u00a0la presencia de errores ostensibles y trascendentes que incidan en el \u00a0sentido \u00a0de \u00a0la \u00a0determinaci\u00f3n, siendo carga del impugnante se\u00f1alar la v\u00eda de \u00a0la infracci\u00f3n, la clase de error, su modalidad y trascendencia. \u00a0\u00a0<\/p>\n<p>Empero, \u00a0 las \u00a0pautas \u00a0precedentes \u00a0fueron \u00a0totalmente \u00a0desatendidas, \u00a0porque \u00a0el \u00a0defensor \u00a0no guarda un orden l\u00f3gico y la \u00a0falta \u00a0de \u00a0claridad \u00a0del \u00a0escrito \u00a0torna problem\u00e1tico dilucidar la pretensi\u00f3n, \u00a0pues \u00a0al \u00a0acusar \u00a0al \u00a0Tribunal \u00a0de \u00a0violar \u00a0indirectamente \u00a0la ley, \u00abpor \u00a0 \u00a0 error \u00a0 \u00a0 de \u00a0 \u00a0derecho, \u00a0 \u00a0por \u00a0 \u00a0falso \u00a0 \u00a0juicio \u00a0 \u00a0de \u00a0identidad\u00bb, \u00a0con relaci\u00f3n \u00a0a \u00a0 la \u00a0 indagatoria \u00a0 de \u00a0 Jos\u00e9 \u00a0 Santos \u00a0 Castillo \u00a0Prieto \u00a0en instrucci\u00f3n y su ampliaci\u00f3n en juicio por \u00a0tacharla \u00a0de \u00a0contradictoria, no hace m\u00e1s que desconocer la metodolog\u00eda propia \u00a0de \u00a0 la \u00a0 casaci\u00f3n, \u00a0en \u00a0cuanto \u00a0no \u00a0es \u00a0compatible \u00a0atribuir \u00a0un \u00a0error \u00a0 de \u00a0derecho \u00a0mediante \u00a0un \u00a0falso \u00a0juicio \u00a0de \u00a0identidad, \u00a0porque \u00a0seg\u00fan se acaba de ilustrar, esta alternativa es \u00a0una \u00a0de las modalidades de error de hecho. \u00a0\u00a0<\/p>\n<p>Seg\u00fan \u00a0se \u00a0observa, \u00a0el representante de la \u00a0defensa \u00a0se limita a expresar su opini\u00f3n mediante un alegato tan desprovisto de \u00a0t\u00e9cnica, \u00a0que no logra ni la categor\u00eda de argumento de instancia y en su af\u00e1n \u00a0por \u00a0desligar al encartado del acontecer delictivo, pretende brindar una postura \u00a0subjetiva \u00a0y \u00a0alejada de los medios de prueba, incluso sin hacer ning\u00fan tipo de \u00a0confrontaci\u00f3n \u00a0a las premisas planteadas en las providencias.\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>El \u00a0 planteamiento \u00a0 seg\u00fan \u00a0 el \u00a0cual \u00a0se \u00a0distorsion\u00f3 \u00a0 el \u00a0 alcance \u00a0 de \u00a0 la \u00a0 indagatoria \u00a0 rendida \u00a0por \u00a0Jos\u00e9 \u00a0 Santos \u00a0Castillo \u00a0Prieto, \u00a0resulta \u00a0infundado \u00a0y \u00a0desconoce la realidad procesal, pues el propio Tribunal cuestion\u00f3 \u00a0el \u00a0giro \u00a0de \u00a0ese \u00a0relato \u00a0y refiri\u00f3 que \u00ab(\u2026) Sin \u00a0embargo, \u00a0valorado \u00a0en conjunto el material probatorio que contiene este proceso \u00a0penal, \u00a0(\u2026) \u00a0 bajo \u00a0ning\u00fan \u00a0derrotero \u00a0se \u00a0halla \u00a0credibilidad \u00a0a \u00a0lo \u00a0manifestado \u00a0por \u00a0el \u00a0implicado, \u00a0(\u2026) \u00a0 por \u00a0cuanto \u00a0encuentra \u00a0demasiadas \u00a0inconsistencias en su dicho y advierte m\u00faltiples \u00a0quimeras \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(\u2026)12\u00bb. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0precis\u00f3 \u00a0el \u00a0juzgador \u00a0que \u00a0en la \u00a0indagatoria \u00a0rendida \u00a0el \u00a030 de agosto de 2010, manifest\u00f3 conocer al ofendido y \u00a0haber \u00a0suscrito \u00a0con \u00a0este \u00a0el contrato de compraventa del veh\u00edculo, pero en la \u00a0audiencia \u00a0p\u00fablica, declar\u00f3 ser un intermediario en la negociaci\u00f3n, en raz\u00f3n \u00a0a \u00a0que \u00a0el \u00a0vendedor Luis Mu\u00f1oz, no pod\u00eda aparecer en el negocio jur\u00eddico por \u00a0no \u00a0tener \u00a0c\u00e9dula \u00a0colombiana. \u00a0Sobre \u00a0\u00e9ste \u00a0personaje \u00a0dijo \u00a0el procesado, se \u00a0trataba \u00a0de un mec\u00e1nico y pintor, que le arregl\u00f3 un veh\u00edculo de su propiedad, \u00a0sin \u00a0 embargo \u00a0 al \u00a0 requerirle \u00a0 su \u00a0 ubicaci\u00f3n \u00a0 no \u00a0 suministr\u00f3 \u00a0 datos \u00a0al \u00a0efecto. \u00a0\u00a0<\/p>\n<p>En \u00a0estas \u00a0condiciones, \u00a0la \u00a0propuesta \u00a0es \u00a0inadmisible \u00a0porque, \u00a0como qued\u00f3 expuesto, el procesado efectivamente vari\u00f3 la \u00a0versi\u00f3n \u00a0 de \u00a0 los \u00a0 hechos; \u00a0 por \u00a0tanto, \u00a0quien \u00a0pretende \u00a0distorsionar \u00a0esta \u00a0circunstancia \u00a0es \u00a0el \u00a0abogado \u00a0en \u00a0su \u00a0aspiraci\u00f3n \u00a0de \u00a0justificar \u00a0una tercera \u00a0evaluaci\u00f3n por parte de la Corte. \u00a0\u00a0<\/p>\n<p>Lo mismo ocurre con Medardo Mera, a quien el \u00a0enjuiciado \u00a0primero \u00a0se\u00f1al\u00f3 \u00a0como \u00a0la \u00a0persona \u00abde \u00a0quien \u00a0hab\u00eda \u00a0adquirido \u00a0el veh\u00edculo por comisi\u00f3n\u00bb, \u00a0para \u00a0 \u00a0 \u00a0luego \u00a0 \u00a0 \u00a0decir \u00a0 \u00a0 \u00a0que \u00a0 \u00a0 \u00a0solo \u00a0 \u00a0 \u00a0fue \u00a0 \u00a0 \u00a0un \u00a0 \u00a0 \u00a0\u00abtramitador\u00bb. \u00a0Con \u00a0esto, \u00a0el \u00a0letrado \u00a0pretende \u00a0desconocer, \u00a0como \u00a0lo \u00a0advirtieron \u00a0los \u00a0falladores, \u00a0que Castillo \u00a0 \u00a0 \u00a0Prieto \u00a0 \u00a0 fue \u00a0quien \u00a0entreg\u00f3 a Eduardo Rodr\u00edguez \u00a0Quiroga, \u00a0el manifiesto de importaci\u00f3n del veh\u00edculo, \u00a0que \u00a0result\u00f3 \u00a0ap\u00f3crifo, \u00a0gestion\u00f3 \u00a0los \u00a0documentos para que la matr\u00edcula del \u00a0automotor \u00a0quedara \u00a0radicada \u00a0en el municipio de Floridablanca y le dijo que era \u00a0mejor \u00a0que \u00a0dicho \u00a0manifiesto del 15 de mayo de 1992 apareciera a su nombre como \u00a0importador, pese a que para esa fecha no era el propietario. \u00a0\u00a0<\/p>\n<p>Estas \u00a0reflexiones, que conforman un juicio \u00a0de \u00a0responsabilidad \u00a0atribuible \u00a0al \u00a0procesado, \u00a0evidencian \u00a0la \u00a0precariedad del \u00a0reproche. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En cuanto \u00a0a \u00a0 la \u00a0 postulaci\u00f3n \u00a0de \u00a0un \u00a0error \u00a0de \u00a0derecho \u00a0respecto \u00a0del \u00a0manifiesto \u00a0de \u00a0importaci\u00f3n, \u00a0seg\u00fan se logra entender, el censor aduce que no existe prueba de \u00a0que \u00a0su \u00a0defendido \u00a0lo \u00a0hubiese \u00a0falsificado \u00a0y, \u00a0a \u00a0su \u00a0juicio, una valoraci\u00f3n \u00a0correcta \u00a0 del \u00a0 documento, \u00a0 debi\u00f3 \u00a0 llevar \u00a0 al \u00a0 Tribunal \u00a0 a \u00a0 aplicar \u00a0 la \u00a0duda. \u00a0 \u00a0\u00a0<\/p>\n<p>El \u00a0planteamiento del reparo es incorrecto, \u00a0porque \u00a0no \u00a0guarda \u00a0relaci\u00f3n \u00a0con \u00a0alguna \u00a0de \u00a0las \u00a0hip\u00f3tesis \u00a0susceptibles de \u00a0cuestionar \u00a0la \u00a0aducida \u00a0modalidad \u00a0de infracci\u00f3n, -falso juicio de legalidad y \u00a0falso \u00a0juicio de convicci\u00f3n-, y con ello nuevamente soslaya los requisitos para \u00a0la \u00a0fundamentaci\u00f3n \u00a0y \u00a0formulaci\u00f3n \u00a0del \u00a0cargo, \u00a0desconoce \u00a0los \u00a0principios de \u00a0claridad, \u00a0precisi\u00f3n, \u00a0autonom\u00eda y no contradicci\u00f3n de las causales y adem\u00e1s \u00a0se limita a realizar reparos gen\u00e9ricos, apenas enunciativos. \u00a0\u00a0<\/p>\n<p>Importa \u00a0recordar \u00a0que \u00a0la \u00a0posibilidad \u00a0de \u00a0demostrar \u00a0la \u00a0falta \u00a0de reconocimiento de la duda por la v\u00eda indirecta, impone \u00a0al \u00a0 \u00a0recurrente \u00a0 el \u00a0 deber \u00a0 de \u00a0 concretar \u00a0 el \u00a0 error, \u00a0 de \u00a0 hecho \u00a0o \u00a0de derecho, la prueba o pruebas \u00a0sobre \u00a0las que recae y demostrar su incidencia en la transgresi\u00f3n de la ley. Si \u00a0se \u00a0 trata \u00a0 de \u00a0un \u00a0yerro \u00a0de \u00a0hecho, \u00a0es \u00a0necesario \u00a0indicar \u00a0la \u00a0modalidad o especie del mismo, es decir, \u00a0-falso \u00a0juicio \u00a0de \u00a0existencia- \u00a0por \u00a0omisi\u00f3n \u00a0o \u00a0suposici\u00f3n, -falso juicio de \u00a0identidad- \u00a0 por \u00a0 distorsi\u00f3n, \u00a0 cercenamiento \u00a0 o \u00a0 adici\u00f3n \u00a0o, \u00a0\u2013falso raciocinio-. \u00a0\u00a0<\/p>\n<p>Si es de derecho, \u00a0se \u00a0 \u00a0materializa \u00a0 a \u00a0 trav\u00e9s \u00a0 del \u00a0 \u2013falso \u00a0juicio \u00a0de \u00a0legalidad- \u00a0cuando \u00a0aprecia \u00a0los \u00a0elementos \u00a0de \u00a0convencimiento no obstante haber sido aportados con \u00a0violaci\u00f3n \u00a0de \u00a0las \u00a0formalidades \u00a0legales para su aducci\u00f3n o incorporaci\u00f3n al \u00a0proceso. \u00a0 \u00a0O \u00a0 \u00a0mediante \u00a0 \u00a0el \u00a0 \u00a0\u2013falso \u00a0juicio \u00a0de \u00a0convicci\u00f3n- \u00a0en \u00a0donde se parte de que la prueba \u00a0respeta \u00a0las \u00a0normas \u00a0relacionadas \u00a0con \u00a0su \u00a0pr\u00e1ctica, pero el legislador le ha \u00a0conferido un valor determinado, que es ignorado por el fallador. \u00a0\u00a0<\/p>\n<p>En \u00a0cualquier \u00a0caso, \u00a0no \u00a0es suficiente con \u00a0invocar \u00a0la \u00a0falta \u00a0de \u00a0reconocimiento, \u00a0como ocurre en la presente, sino que es \u00a0imperativo \u00a0 acreditar \u00a0 la \u00a0 ocurrencia \u00a0 del \u00a0yerro \u00a0de \u00a0cara \u00a0a \u00a0la \u00a0realidad \u00a0procesal. \u00a0\u00a0<\/p>\n<p>Sin \u00a0 embargo, \u00a0 ninguna \u00a0 situaci\u00f3n \u00a0de \u00a0incertidumbre \u00a0se \u00a0avizora \u00a0en \u00a0los \u00a0fallos de instancia. L\u00e9anse las siguientes \u00a0glosas \u00a0 planteadas \u00a0 por \u00a0 el \u00a0Ad \u00a0quem: \u00a0\u00a0<\/p>\n<p>\u00ab(\u2026) En el caso bajo examen y a partir \u00a0del \u00a0 contenido \u00a0 del \u00a0 expediente, \u00a0se \u00a0advierte \u00a0que \u00a0el \u00a0se\u00f1or \u00a0Castillo \u00a0 \u00a0 \u00a0Prieto \u00a0 \u00a0 fue \u00a0la \u00a0persona \u00a0que \u00a0enajen\u00f3 \u00a0el veh\u00edculo clase tracto cami\u00f3n \u00a0(sic), \u00a0marca \u00a0Kenworth, \u00a0modelo \u00a01992, \u00a0el 25 de agosto de 2005 en la Ciudad de \u00a0C\u00facuta \u00a0(Norte \u00a0de \u00a0Santander) \u00a0al \u00a0se\u00f1or \u00a0Eduardo \u00a0Rodr\u00edguez \u00a0Quiroga, \u00a0esta \u00a0aserci\u00f3n \u00a0se corrobora con la lectura del contenido del contrato de compraventa \u00a0visto a folio 9, cuaderno 1. \u00a0\u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>Empero, \u00a0 en \u00a0 el \u00a0citado \u00a0contrato \u00a0se \u00a0comprometi\u00f3 \u00a0 el \u00a0vendedor \u00a0(implicado) \u00a0a \u00a0gestionar \u00a0cualquier \u00a0documento \u00a0de \u00a0tr\u00e1mite \u00a0legal \u00a0que se llegare a requerir y \u00a0 efectivamente, \u00a0 as\u00ed \u00a0 lo \u00a0Santos \u00a0Castillo \u00a0quien le ofreci\u00f3 a la v\u00edctima un negocio \u00a0aparentemente \u00a0bueno \u00a0y \u00a0cumpli\u00f3 \u00a0con \u00a0lo estipulado, cuando el 1 de octubre de \u00a02004, \u00a0le \u00a0entreg\u00f3 \u00a0un \u00a0documento \u00a0en \u00a0el \u00a0que \u00a0se \u00a0indicaba \u00a0como \u00a0titular del \u00a0manifiesto \u00a0 de \u00a0importaci\u00f3n \u00a0No. \u00a0011479 \u00a0al \u00a0Se\u00f1or \u00a0Eduardo \u00a0Quiroga \u00a0y \u00a0dos \u00a0fotocopias \u00a0de la Direcci\u00f3n de Tr\u00e1nsito del Magdalena, contentivo del traslado \u00a0de \u00a0la \u00a0cuenta \u00a0del \u00a0veh\u00edculo, \u00a0para \u00a0el municipio de Floridablanca, hasta este \u00a0momento \u00a0la \u00a0compraventa \u00a0del \u00a0citado \u00a0veh\u00edculo \u00a0lleg\u00f3 \u00a0a \u00a0buen \u00a0t\u00e9rmino, \u00a0en \u00a0atenci\u00f3n \u00a0a \u00a0que se realiz\u00f3 el pago, se entreg\u00f3 el bien objeto de compra y se \u00a0adjudicaron los documentos pertinentes. \u00a0\u00a0<\/p>\n<p>No obstante, el 13 de octubre de 2008, el \u00a0automotor \u00a0fue \u00a0hurtado \u00a0al \u00a0comprador, \u00a0tal \u00a0como \u00a0se \u00a0describe \u00a0en la denuncia \u00a0instaurada \u00a0por \u00e9ste ante las autoridades pertinentes y al realizar el tr\u00e1mite \u00a0con \u00a0la \u00a0aseguradora \u00a0Colseguros \u00a0para la debida indemnizaci\u00f3n por p\u00e9rdida del \u00a0veh\u00edculo, \u00a0se \u00a0enter\u00f3 \u00a0con \u00a0desconcierto \u00a0que \u00a0la negativa de la aseguradora a \u00a0pagar \u00a0su \u00a0obligaci\u00f3n \u00a0se \u00a0deb\u00eda \u00a0a \u00a0que \u00a0\u201c\u2026el proceso de importaci\u00f3n del \u00a0rodante \u00a0asegurado \u00a0presenta \u00a0vicios en el soporte pertinente..\u201d; es decir, el \u00a0manifiesto \u00a0de \u00a0importaci\u00f3n era falso, documento este que hab\u00eda sido tramitado \u00a0por \u00a0Santos \u00a0Castillo \u00a0a \u00a0nombre del comprador. \u00a0\u00a0<\/p>\n<p>Esta \u00a0situaci\u00f3n \u00a0fue \u00a0corroborada por el \u00a0vendedor, \u00a0 \u00a0aqu\u00ed \u00a0 \u00a0implicado, \u00a0 \u00a0Jos\u00e9 \u00a0 Santos \u00a0Castillo, \u00a0quien \u00a0luego \u00a0de \u00a0varias \u00a0comunicaciones \u00a0telef\u00f3nicas, \u00a0 logr\u00f3 \u00a0 reunirse \u00a0 con \u00a0 Eduardo \u00a0 Quiroga \u00a0 y \u00a0advirtiendo \u00a0la \u00a0irregularidad \u00a0 decidi\u00f3 \u00a0 suscribir \u00a0 con \u00a0 \u00e9ste \u00a0 un \u00a0 documento \u00a0 denominado \u00a0\u201crescisi\u00f3n \u00a0de \u00a0contrato\u201d, \u00a0figura \u00a0prevista \u00a0en \u00a0el \u00a0Art. 1200 CC, el cual \u00a0prev\u00e9 \u00a0la \u00a0extinci\u00f3n \u00a0por el acuerdo mutuo de las voluntades de las partes del \u00a0contrato. \u00a0Es \u00a0decir, \u00a0de \u00a0la \u00a0misma \u00a0forma en que las partes en ejercicio de la \u00a0autonom\u00eda \u00a0de \u00a0la \u00a0voluntad \u00a0prevista \u00a0en \u00a0el \u00a0Art. 1197 CC crearon el contrato \u00a0tambi\u00e9n \u00a0pueden \u00a0extinguirlo. Entre tanto, as\u00ed lo dispusieron el 12 de mayo de \u00a02009, \u00a0 oblig\u00e1ndose \u00a0 el \u00a0 se\u00f1or \u00a0 Jos\u00e9 \u00a0 Santos \u00a0Castillo a cancelar a favor de Eduardo Rodr\u00edguez la \u00a0suma \u00a0de \u00a0$80.000.000 \u00a0millones \u00a0de \u00a0pesos, entre otras consideraciones, esto en \u00a0atenci\u00f3n \u00a0a: \u00a0\u201cel \u00a0hecho o negativa de la aseguradora colseguros para pagar o \u00a0reconocer \u00a0el \u00a0siniestro \u00a0por \u00a0hurto, \u00a0a \u00a0favor \u00a0del \u00a0se\u00f1or \u00a0Eduardo Rodr\u00edguez \u00a0Quiroga, \u00a0 argumentando \u00a0 falencias \u00a0 en \u00a0 la \u00a0 documentaci\u00f3n \u00a0referente \u00a0a \u00a0la \u00a0impostaci\u00f3n \u00a0(sic) del referido carro, que como consecuencia se objet\u00f3 el pago \u00a0por \u00a0parte de la aseguradora por considerarlo objeto il\u00edcito, trayendo notables \u00a0perjuicios \u00a0para \u00a0Eduardo Rodr\u00edguez Quiroga, ya que no obstante haber pagado la \u00a0totalidad \u00a0del \u00a0veh\u00edculo \u00a0al \u00a0se\u00f1or \u00a0Jos\u00e9 \u00a0Santos \u00a0castillo \u00a0Prieto (sic), ha \u00a0quedado \u00a0 sin \u00a0 el \u00a0 mismo \u00a0veh\u00edculo \u00a0por \u00a0haber \u00a0sido \u00a0v\u00edctima \u00a0de \u00a0su \u00a0hurto \u00a0(\u2026)13\u00bb\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Lo \u00a0cierto \u00a0es, que los juzgadores lograron \u00a0acreditar \u00a0con \u00a0claridad \u00a0y \u00a0precisi\u00f3n \u00a0el \u00a0compromiso \u00a0penal \u00a0que \u00a0le ata\u00f1e a \u00a0Castillo \u00a0Prieto, \u00a0pero \u00a0el \u00a0actor \u00a0no \u00a0confronta \u00a0los \u00a0argumentos \u00a0expuestos, \u00a0ni \u00a0desarrolla \u00a0la \u00a0causal de \u00a0violaci\u00f3n \u00a0invocada, \u00a0no concreta cargo alguno y se limita a hacer una menci\u00f3n \u00a0gen\u00e9rica \u00a0de los hechos aludidos sin demostrar concretamente un error junto con \u00a0su incidencia en la decisi\u00f3n y la necesidad de superarlo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Con base \u00a0en \u00a0la \u00a0causal \u00a0primera, \u00a0propone \u00a0un \u00a0error \u00a0de \u00a0derecho \u00a0en la valoraci\u00f3n del \u00a0contrato \u00a0de \u00a0rescisi\u00f3n, porque el Tribunal no tuvo en cuenta que se configur\u00f3 \u00a0un incumplimiento contractual y no un delito. \u00a0 \u00a0\u00a0<\/p>\n<p>Son recurrentes las imprecisiones en las que \u00a0incurre \u00a0el abogado, confunde reiteradamente el error \u00a0de \u00a0 hecho \u00a0 con \u00a0 el \u00a0de \u00a0derecho, \u00a0 el \u00a0memorial \u00a0desconoce \u00a0abiertamente \u00a0las \u00a0exigencias \u00a0de \u00a0\u00edndole formal y sustancial que hacen posible acudir a esta sede \u00a0en \u00a0cuanto \u00a0a \u00a0la obligaci\u00f3n de enunciar la causal, formular el cargo e indicar \u00a0en \u00a0forma \u00a0clara \u00a0y precisa los fundamentos que le asisten, as\u00ed como las fallas \u00a0atribuibles \u00a0al \u00a0fallo, por lo que en lo referente a la t\u00e9cnica, en el presente \u00a0apartado se estar\u00e1 a lo se\u00f1alado en los puntos precedentes. \u00a0\u00a0<\/p>\n<p>A ello se suma que tampoco le asiste raz\u00f3n \u00a0al \u00a0demandante \u00a0en \u00a0sus \u00a0reparos \u00a0porque \u00a0esa \u00a0discusi\u00f3n \u00a0fue \u00a0resuelta por los \u00a0falladores, \u00a0al acreditar que comunicada esta situaci\u00f3n irregular del documento \u00a0de \u00a0importaci\u00f3n \u00a0por \u00a0el \u00a0denunciante \u00a0a \u00a0Jos\u00e9 Santos \u00a0Castillo \u00a0Prieto, \u00a0este \u00a0acept\u00f3 \u00a0su responsabilidad y \u00a0as\u00ed \u00a0qued\u00f3 \u00a0demostrado \u00a0con \u00a0la \u00a0rescisi\u00f3n \u00a0del \u00a0contrato \u00a0del \u00a012 de mayo de \u00a0200914, \u00a0donde se dej\u00f3 expresa constancia que su suscripci\u00f3n obedec\u00eda a \u00a0las \u00a0inconsistencias en la documentaci\u00f3n de importaci\u00f3n del veh\u00edculo y que el \u00a0encartado \u00a0se \u00a0obligaba \u00a0a \u00a0cancelar \u00a0la \u00a0suma \u00a0de $80.000,000,oo a Eduardo \u00a0 \u00a0 \u00a0Rodr\u00edguez \u00a0 \u00a0 Quiroga \u00a0como \u00a0compensaci\u00f3n, \u00a0de \u00a0los \u00a0que \u00a0solo \u00a0le \u00a0entreg\u00f3 \u00a0$10.000.000,oo. \u00a0\u00a0<\/p>\n<p>El planteamiento gira entorno a reflexiones \u00a0desprovistas \u00a0de \u00a0t\u00e9cnica, \u00a0que incluso eluden enfrentar el alcance real de los \u00a0reproches \u00a0expuestos \u00a0por \u00a0el \u00a0Tribunal \u00a0sin ning\u00fan efecto \u00fatil en la presente \u00a0solicitud de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Al amparo \u00a0de \u00a0la \u00a0causal \u00a0tercera \u00a0del \u00a0canon \u00a0207 \u00a0de \u00a0la \u00a0Ley \u00a0600 \u00a0de \u00a02000, \u00a0que \u00a0consagra \u00a0como motivo de casaci\u00f3n \u00a0\u00abcuando \u00a0la \u00a0sentencia se haya dictado en un juicio \u00a0viciado \u00a0de nulidad\u00bb, acusa \u00a0a \u00a0 \u00a0la \u00a0 \u00a0sentencia \u00a0 \u00a0de \u00a0 \u00a0desconocer \u00a0 \u00a0el \u00a0 principio \u00a0 de \u00a0 investigaci\u00f3n \u00a0integral. \u00a0 \u00a0\u00a0<\/p>\n<p>La denuncia por este camino obliga al censor \u00a0a \u00a0ce\u00f1irse \u00a0a \u00a0los \u00a0requerimientos \u00a0que \u00a0ha \u00a0puntualizado \u00a0la jurisprudencia en \u00a0concreto, \u00a0a \u00a0reclamar, \u00a0seg\u00fan las previsiones del art\u00edculo 217 del C\u00f3digo de \u00a0Procedimiento \u00a0Penal, \u00a0la declaratoria de nulidad, pero en ning\u00fan caso, como lo \u00a0hizo en el libelo, pedir la absoluci\u00f3n de su procesado. \u00a0\u00a0<\/p>\n<p>Los \u00a0reproches \u00a0por \u00a0esta \u00a0senda imponen al \u00a0demandante \u00a0concretar los fundamentos que le asisten para descubrir el menoscabo \u00a0de \u00a0alguna \u00a0de \u00a0las \u00a0garant\u00edas \u00a0que orientan el proceso penal o que integran su \u00a0estructura \u00a0b\u00e1sica, \u00a0al \u00a0tenor \u00a0de \u00a0la \u00a0disposici\u00f3n 309 ib\u00eddem, detallando la \u00a0clase \u00a0 de \u00a0nulidad \u00a0que \u00a0invoca. \u00a0Le \u00a0corresponde \u00a0igualmente \u00a0revelar \u00a0que \u00a0la \u00a0irregularidad \u00a0efectivamente \u00a0tiene \u00a0el \u00a0poder \u00a0de quebrantar garant\u00edas o bases \u00a0fundamentales \u00a0de \u00a0la instrucci\u00f3n o del juicio y demostrar que el interesado no \u00a0contribuy\u00f3 \u00a0a la producci\u00f3n del acto tachado de irregular, salvo el caso de la \u00a0ausencia \u00a0de \u00a0defensa \u00a0t\u00e9cnica \u00a0(principio \u00a0de \u00a0protecci\u00f3n) \u00a0o \u00a0frente \u00a0a \u00a0una \u00a0actuaci\u00f3n \u00a0 an\u00f3mala \u00a0 que \u00a0 posteriormente \u00a0 sea \u00a0 ratificada \u00a0 (principio \u00a0de \u00a0convalidaci\u00f3n)15. \u00a0As\u00ed mismo, debe sustentar \u00a0porque \u00a0la \u00a0nulidad \u00a0es \u00a0la \u00a0\u00fanica \u00a0forma \u00a0de enmendar el agravio (principio de \u00a0residualidad) \u00a0que \u00a0le produce un da\u00f1o determinado, desde qu\u00e9 momento procesal \u00a0debe \u00a0 retrotraerse \u00a0 la \u00a0 actuaci\u00f3n \u00a0 y \u00a0la \u00a0ventaja \u00a0que \u00a0obtendr\u00eda \u00a0con \u00a0su \u00a0declaratoria. \u00a0\u00a0<\/p>\n<p>Se \u00a0resalta \u00a0que \u00a0no \u00a0cualquier \u00a0anomal\u00eda \u00a0conduce \u00a0indefectiblemente a la declaratoria de nulidad, sino que la misma tiene \u00a0que \u00a0ser, \u00a0de \u00a0tal magnitud, que conculque la esencia del juicio y el derecho al \u00a0debido \u00a0 \u00a0proceso \u00a0 \u00a0con \u00a0 \u00a0una \u00a0 \u00a0incidencia \u00a0 \u00a0espec\u00edfica \u00a0 \u00a0en \u00a0 \u00a0el \u00a0 fallo \u00a0recurrido. \u00a0\u00a0<\/p>\n<p>Cuando \u00a0se \u00a0postula \u00a0el desconocimiento del \u00a0principio \u00a0de \u00a0investigaci\u00f3n integral, contenido del art\u00edculo 20 de la Ley 600 \u00a0de \u00a02000, \u00a0es \u00a0preciso \u00a0demostrar \u00a0que \u00a0el instructor se concentr\u00f3 en practicar \u00a0aquellos \u00a0elementos \u00a0de \u00a0convicci\u00f3n que desfavorecen al imputado o a las dem\u00e1s \u00a0partes, omitiendo recaudar las probanzas que los favorecen. \u00a0\u00a0<\/p>\n<p>Empero, \u00a0el \u00a0abogado \u00a0no \u00a0profundiza \u00a0en su \u00a0formulaci\u00f3n, \u00a0 pues \u00a0 ni \u00a0 siquiera \u00a0concreta \u00a0que \u00a0hubiesen \u00a0favorecido \u00a0a \u00a0su \u00a0representado \u00a0y \u00a0solo \u00a0exterioriza \u00a0su \u00a0intenci\u00f3n de cuestionar la apreciaci\u00f3n \u00a0probatoria, \u00a0aduciendo que no se investig\u00f3 sobre la propiedad del veh\u00edculo, ni \u00a0la \u00a0persona \u00a0que realiz\u00f3 los tramites del manifiesto de importaci\u00f3n; que en la \u00a0indagatoria \u00a0no \u00a0se \u00a0realizaron \u00a0las \u00a0preguntas \u00a0suficientes \u00a0y \u00a0necesarias para \u00a0determinar \u00a0todo \u00a0lo \u00a0relacionado con el contrato y que no se tuvo en cuenta que \u00a0el \u00a0procesado \u00a0se \u00a0encontraba \u00a0muy \u00a0ocupado para defenderse; afirmaciones que de \u00a0ninguna \u00a0manera \u00a0constituyen \u00a0reparos \u00a0sensatos \u00a0y \u00a0procedentes para reclamar un \u00a0quebranto \u00a0a \u00a0la estructura del proceso o la lesi\u00f3n de garant\u00edas fundamentales \u00a0del acusado. \u00a0\u00a0<\/p>\n<p>Olvida adem\u00e1s que, en caso de discrepancia \u00a0prima \u00a0el juicio del juzgador, quien est\u00e1 constitucional y legalmente facultado \u00a0para \u00a0 apreciar \u00a0 los \u00a0 medios \u00a0 de \u00a0prueba \u00a0y \u00a0asignarles \u00a0m\u00e9rito \u00a0persuasivo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por \u00a0\u00faltimo, \u00a0 enuncia \u00a0 un \u00a0t\u00edtulo \u00a0denominado \u00a0casaci\u00f3n \u00a0oficiosa, \u00a0que \u00a0tampoco \u00a0sustenta, \u00a0no desarrolla el sentido de la presunta violaci\u00f3n y la relevancia de \u00a0ella \u00a0en \u00a0la \u00a0determinaci\u00f3n recurrida, lo que conduce a inadmitir la demanda en \u00a0atenci\u00f3n \u00a0a \u00a0que \u00a0la Sala no encuentra que en la actuaci\u00f3n causales de nulidad \u00a0ni infracciones de derechos fundamentales. \u00a0 \u00a0\u00a0<\/p>\n<p>3. \u00a0Como \u00a0queda \u00a0expuesto, \u00a0la \u00a0demanda \u00a0formulada \u00a0no cumple con las m\u00ednimas exigencias para su \u00a0admisi\u00f3n, \u00a0toda \u00a0vez \u00a0que \u00a0en \u00a0su \u00a0confecci\u00f3n no se atendieron los par\u00e1metros \u00a0legalmente \u00a0 establecidos \u00a0 y \u00a0ampliamente \u00a0ense\u00f1ados \u00a0por \u00a0la \u00a0jurisprudencia, \u00a0esencialmente, \u00a0en lo que corresponde a la correcta selecci\u00f3n de las causales y \u00a0su \u00a0adecuada \u00a0fundamentaci\u00f3n, en orden a la demostraci\u00f3n de las falencias y el \u00a0restablecimiento \u00a0de \u00a0la \u00a0legalidad \u00a0acorde \u00a0con los motivos expuestos.\u00a0 El \u00a0demandante \u00a0omite \u00a0la \u00a0carga \u00a0de \u00a0sustentar \u00a0adecuadamente \u00a0los \u00a0par\u00e1metros \u00a0de \u00a0apreciaci\u00f3n \u00a0racional a partir del propio contenido de la sentencia, no precisa \u00a0el \u00a0error, \u00a0su \u00a0fundamentaci\u00f3n \u00a0y \u00a0trascendencia \u00a0en \u00a0el fallo y simplemente se \u00a0centra \u00a0en \u00a0negarle \u00a0raz\u00f3n \u00a0y tratar de anteponer su \u00f3ptica apreciativa con el \u00a0objetivo \u00a0de prolongar el debate efectuado por el juzgador, desconociendo que el \u00a0proceso \u00a0concluy\u00f3 con el fallo de segundo grado y que a esta sede llega bajo el \u00a0amparo de la doble presunci\u00f3n de acierto y legalidad. \u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Corte Suprema \u00a0de \u00a0Justicia, \u00a0Sala \u00a0de \u00a0Casaci\u00f3n Penal, administrando justicia en nombre de la \u00a0Rep\u00fablica y por autoridad de la ley, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>Primero. \u00a0INADMITIR \u00a0la \u00a0demanda \u00a0examinada. \u00a0\u00a0<\/p>\n<p>Segundo. \u00a0Contra \u00a0esta decisi\u00f3n no procede recurso alguno. \u00a0\u00a0<\/p>\n<p>NOTIF\u00cdQUESE Y C\u00daMPLASE \u00a0<\/p>\n<p>GUSTAVO \u00a0 \u00a0ENRIQUE \u00a0 \u00a0MALO FERN\u00c1NDEZ \u00a0\u00a0<\/p>\n<p>Presidente \u00a0<\/p>\n<p>JOS\u00c9 FRANCISCO ACU\u00d1A VIZCAYA \u00a0<\/p>\n<p>JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>FERNANDO ALBERTO CASTRO CABALLERO \u00a0<\/p>\n<p>EUGENIO \u00a0 \u00a0 \u00a0FERN\u00c1NDEZ CARLIER \u00a0\u00a0<\/p>\n<p>LUIS \u00a0 \u00a0ANTONIO \u00a0 \u00a0HERN\u00c1NDEZ BARBOSA \u00a0\u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>PATRICIA SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p>1 \u00a0Folio \u00a0 05 \u00a0 Cuaderno \u00a0 del \u00a0 Tribunal. \u00a0\u00a0<\/p>\n<p>2 \u00a0Folio 27 Cuaderno Original No. 1 \u00a0\u00a0<\/p>\n<p>3 \u00a0Folio 73 al 76 Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>4 \u00a0Folio 215 Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>5 \u00a0Folio 219 a 227 Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>6 \u00a0Folio \u00a0 5 \u00a0 Cuaderno de la Causa. \u00a0\u00a0<\/p>\n<p>7 \u00a0Folio \u00a031 \u00a0al \u00a033 \u00a0Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>8 \u00a0Folios 95 al 103, 210 al 212, 232 al 233 y 269 al 273 \u00a0Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>9 \u00a0Folios 286 al 307 Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>10 \u00a0Folio 05 al 13 Cuaderno del Tribunal. \u00a0\u00a0<\/p>\n<p>11 \u00a0Folio 55 Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>12 \u00a0P\u00e1gina \u00a0 \u00a010 \u00a0 \u00a0de \u00a0 la \u00a0 sentencia \u00a0 de \u00a0 segunda \u00a0instancia. \u00a0\u00a0<\/p>\n<p>13 \u00a0P\u00e1gina 6 y 7 Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>14 \u00a0Folio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a026 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Ib\u00eddem. \u00a0\u00a0<\/p>\n<p>15 \u00a0Art\u00edculo 310 de la Ley 600 de 2000- \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0\u00a0 Eyder Pati\u00f1o Cabrera \u00a0 Magistrado \u00a0ponente \u00a0\u00a0 AP6589-2016 \u00a0 Radicaci\u00f3n N\u00b0 48425 \u00a0 (Aprobado acta N\u00b0 305) \u00a0 Bogot\u00e1, D. C., veintiocho (28) de septiembre \u00a0de dos mil diecis\u00e9is (2016) \u00a0\u00a0 MOTIVO DE LA DECISI\u00d3N \u00a0 Se pronuncia la Sala sobre la admisibilidad \u00a0de \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0por \u00a0el \u00a0apoderado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-33680","post","type-post","status-publish","format-standard","hentry","category-25"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/33680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=33680"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/33680\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=33680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=33680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=33680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}