{"id":3341,"date":"2023-09-08T14:30:01","date_gmt":"2023-09-08T14:30:01","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/16107ago\/"},"modified":"2023-09-08T14:30:01","modified_gmt":"2023-09-08T14:30:01","slug":"16107ago","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/16107ago\/","title":{"rendered":"16107ago"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso N\u00ba 16107 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACION PENAL \u00a0<\/p>\n<p>MAGISTRADO \u00a0PONENTE \u00a0\u00a0<\/p>\n<p>ALVARO \u00a0ORLANDO \u00a0PEREZ \u00a0PINZON \u00a0\u00a0<\/p>\n<p>APROBADO ACTA No. 138 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Santa \u00a0Fe \u00a0de Bogot\u00e1, D. C., quince (15) de agosto del a\u00f1o dos mil \u00a0(2000) \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Resuelve \u00a0la \u00a0Sala \u00a0los \u00a0recursos de reposici\u00f3n interpuestos por el \u00a0se\u00f1or \u00a0ROBERTO \u00a0ANGELO \u00a0FERRARIO \u00a0POZZI \u00a0y \u00a0su defensor contra el auto del 6 de \u00a0junio \u00a0del \u00a0a\u00f1o \u00a0en \u00a0curso, mediante el cual se negaron las pruebas solicitadas \u00a0por ambos. \u00a0\u00a0<\/p>\n<p>ANTECEDENTES \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01. \u00a0Por \u00a0Nota \u00a0Verbal No. 537 de julio 14 de 1999, Estados Unidos de \u00a0Am\u00e9rica \u00a0solicit\u00f3 \u00a0la \u00a0extradici\u00f3n \u00a0del \u00a0ciudadano \u00a0italiano \u00a0ROBERTO \u00a0ANGELO \u00a0FERRARIO \u00a0POZZI, \u00a0contra quien un Gran Jurado Federal de San Juan de Puerto Rico \u00a0expidi\u00f3 \u00a0Pliego \u00a0Acusatorio \u00a0en \u00a0diciembre \u00a07 \u00a0de \u00a01998 \u00a0por conspiraci\u00f3n para \u00a0cometer \u00a0 lavado \u00a0 de \u00a0dinero, \u00a0sustituido \u00a0por \u00a0un \u00a0Segundo \u00a0Pliego \u00a0Acusatorio \u00a0Subsiguiente de fecha diciembre 29 del mismo a\u00f1o. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>El \u00a0se\u00f1or FERRARIO POZZI fue capturado el 16 \u00a0de \u00a0mayo \u00a0de \u00a01999 \u00a0por \u00a0el Departamento Administrativo de Seguridad, atendiendo \u00a0orden expedida por el Fiscal General de la Naci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02. \u00a0El \u00a019 de julio de 1999, el Ministerio de Justicia y del Derecho \u00a0remiti\u00f3 \u00a0a esta Sala la documentaci\u00f3n, traducida y autenticada, que le enviara \u00a0la Embajada de los Estados Unidos de Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a03. \u00a0Por \u00a0auto \u00a0de \u00a0agosto \u00a06 \u00a0de \u00a01999, \u00a0el \u00a0Despacho del Magistrado \u00a0Sustanciador \u00a0 dio \u00a0traslado \u00a0a \u00a0los \u00a0interesados \u00a0en \u00a0este \u00a0tr\u00e1mite \u00a0para \u00a0que \u00a0solicitaran \u00a0las \u00a0pruebas que estimaran necesarias, lo que en efecto hicieron el \u00a0requerido y su defensor. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a04. \u00a0La \u00a0Sala, \u00a0mediante \u00a0providencia \u00a0de \u00a0junio 6 del a\u00f1o en curso, \u00a0neg\u00f3 \u00a0las \u00a0peticiones \u00a0formuladas \u00a0por \u00a0el \u00a0se\u00f1or \u00a0FERRARIO y por su defensor, \u00a0decisi\u00f3n \u00a0 que \u00a0 fue \u00a0 objeto \u00a0 de \u00a0 la \u00a0impugnaci\u00f3n \u00a0que \u00a0por \u00a0este \u00a0auto \u00a0se \u00a0resuelve. \u00a0\u00a0<\/p>\n<p>LA \u00a0IMPUGNACION \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Tanto \u00a0el \u00a0defensor como el solicitado inicialmente rechazan, por no \u00a0corresponder \u00a0 a \u00a0la \u00a0realidad, \u00a0la \u00a0afirmaci\u00f3n \u00a0contenida \u00a0en \u00a0el \u00a0resumen \u00a0de \u00a0antecedentes \u00a0consignado \u00a0en \u00a0la \u00a0providencia recurrida, en el sentido de que al \u00a0se\u00f1or \u00a0FERRARIO \u00a0se \u00a0le \u00a0acusa \u00a0\u201cpor \u00a0conspiraci\u00f3n \u00a0para poseer y distribuir \u00a0narc\u00f3ticos y conspiraci\u00f3n para cometer lavado de dinero\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Con \u00a0relaci\u00f3n \u00a0a \u00a0las \u00a0pruebas, dice el defensor que desiste de las \u00a0pedidas \u00a0antes del traslado as\u00ed como de la audiencia para escuchar a su pupilo. \u00a0Insiste \u00a0en \u00a0la \u00a0importancia \u00a0de \u00a0que \u00a0se \u00a0admita el primer Pliego Acusatorio en \u00a0ingl\u00e9s, \u00a0para \u00a0demostrar \u00a0la \u00a0variaci\u00f3n \u00a0que \u00a0luego se le introdujo, lo que le \u00a0permitir\u00eda \u00a0alegar \u00a0m\u00e1s \u00a0tarde \u00a0la \u00a0falta \u00a0de equivalencia de las providencias \u00a0proferidas en el extranjero. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Afirma \u00a0tambi\u00e9n que todas las dem\u00e1s pruebas, como las relacionadas \u00a0con \u00a0la \u00a0forma \u00a0como se constituy\u00f3 la empresa MULTIPIX, el operador phone home, \u00a0el \u00a0 amparo \u00a0 legal \u00a0 de \u00a0 las \u00a0 transferencias \u00a0monetarias \u00a0y \u00a0la \u00a0licencia \u00a0de \u00a0funcionamiento, \u00a0inciden directamente sobre la aplicaci\u00f3n del art\u00edculo 558 del \u00a0C\u00f3digo de Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>Igualmente, reprocha la identificaci\u00f3n que se \u00a0hace \u00a0de \u00a0su \u00a0cliente \u00a0con \u00a0alias Spaguettini, apodo con que se le conoce a otro \u00a0socio \u00a0de \u00a0MULTIPIX, \u00a0GIUSSEPPE PINCHERA, como consta en el affidavit del agente \u00a0especial \u00a0Leo \u00a0Morales \u00a0presentado \u00a0como \u00a0prueba \u00a0en su solicitud de agosto 3 de \u00a01999, punto 9 anexo 9. \u00a0\u00a0<\/p>\n<p>El \u00a0se\u00f1or \u00a0FERRARIO, \u00a0por \u00a0su \u00a0parte, \u00a0hace \u00a0hincapi\u00e9 \u00a0 en \u00a0que \u00a0se \u00a0debe \u00a0decretar \u00a0como \u00a0prueba \u00a0aportada \u00a0el \u00a0superseding \u00a0indictment \u00a098-189 \u00a0(hl) suscrito por un Gran Jurado de Puerto Rico en diciembre \u00a07 \u00a0de \u00a01998, \u00a0porque \u00a0ese sumario norteamericano fue la causa de su detenci\u00f3n y \u00a0toca \u00a0directamente \u00a0con \u00a0el \u00a0concepto \u00a0que habr\u00e1 de rendir la Corte. Realiza la \u00a0comparaci\u00f3n \u00a0entre \u00a0ese \u00a0documento y el anexado por la Embajada Norteamericana, \u00a0para \u00a0demostrar \u00a0que \u00a0aquel fue modificado antes de su traducci\u00f3n al castellano \u00a0como \u00a0se \u00a0deduce de las menciones a Roberto Rodr\u00edguez (a. Pich\u00f3n) que se hacen \u00a0en \u00a0el \u00a0primero y a Ram\u00f3n Rodr\u00edguez (a. Pich\u00f3n) consignadas en el segundo. En \u00a0consecuencia, \u00a0como \u00a0el \u00a0documento \u00a0presentado \u00a0oficialmente no es una copia del \u00a0original, \u00a0se \u00a0incumple \u00a0el \u00a0mandato del art\u00edculo 551 C.P.P. y no se podr\u00e1 dar \u00a0concepto \u00a0favorable para su extradici\u00f3n en t\u00e9rminos del art\u00edculo 558 ib\u00eddem. \u00a0Sin \u00a0embargo, \u00a0si \u00a0no se decreta esa prueba, la Corte conceptuar\u00e1 teniendo como \u00a0fundamento \u00a0una \u00a0documentaci\u00f3n \u00a0no \u00a0ver\u00eddica \u00a0y \u00a0se \u00a0violar\u00e1 \u00a0su \u00a0derecho \u00a0de \u00a0defensa. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Agrega \u00a0que \u00a0las declaraciones de la Fiscal Sanfiorenzo \u2013no \u00a0 \u00a0de \u00a0 \u00a0Guillermo \u00a0 \u00a0Gil \u00a0 \u00a0como \u00a0equivocadamente, \u00a0dice, \u00a0se \u00a0se\u00f1ala en el auto recurrido- y del agente especial \u00a0Smallwood \u00a0contienen \u00a0irregularidades \u00a0que \u00a0las \u00a0invalidan. \u00a0Y \u00a0como \u00a0la \u00a0fiscal \u00a0manifiesta \u00a0anexar \u00a0la \u00a0declaraci\u00f3n \u00a0del \u00a0agente \u00a0especial como evidencia en su \u00a0contra, \u00a0ese \u00a0texto \u00a0hace \u00a0parte \u00a0integrante del superseding indictment. Pero si \u00a0aquella \u00a0se \u00a0suscribi\u00f3 \u00a06 \u00a0meses \u00a0despu\u00e9s \u00a0de \u00a0los indictment, el \u00fanico medio \u00a0probatorio \u00a0en \u00a0el que se apoya es improcedente y por eso la documentaci\u00f3n debe \u00a0desecharse, \u00a0adem\u00e1s \u00a0de haberse preparado despu\u00e9s del env\u00edo de la nota verbal \u00a0No. 274 que solicitaba su captura, lo que la hace ilegal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Expone \u00a0finalmente \u00a0que \u00a0la \u00a0declaraci\u00f3n \u00a0del \u00a0agente \u00a0especial Leo \u00a0Morales, \u00a0quien \u00a0en \u00a0realidad \u00a0fue \u00a0el \u00a0encargado \u00a0de la investigaci\u00f3n del caso \u00a098-189 \u00a0y \u00a0es \u00a0por \u00a0lo \u00a0mismo \u00a0el \u00a0\u00fanico \u00a0soporte \u00a0del \u00a0sumario norteamericano, \u00a0constituye \u00a0una \u00a0prueba \u00a0pertinente, \u00a0conducente y legalmente eficaz, por lo que \u00a0debe aceptarse. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE \u00a0LA \u00a0SALA \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0Sala \u00a0reitera \u00a0su conclusi\u00f3n, expuesta en el auto recurrido, de \u00a0que \u00a0la \u00a0responsabilidad \u00a0no \u00a0es \u00a0tema \u00a0del \u00a0que \u00a0le \u00a0corresponda ocuparse en la \u00a0intervenci\u00f3n \u00a0que \u00a0debe \u00a0cumplir \u00a0dentro del tr\u00e1mite de la extradici\u00f3n. De la \u00a0siguiente \u00a0manera \u00a0se \u00a0pronunci\u00f3, \u00a0por ejemplo, en decisi\u00f3n del 10 de marzo de \u00a01999 ( M. P. Dr. Carlos Eduardo Mej\u00eda Escobar. Rad. No. 14.324 ): \u00a0\u00a0<\/p>\n<p>\u201c&#8230; \u00a0si \u00a0se \u00a0tiene \u00a0en \u00a0cuenta \u00a0que \u00a0la \u00a0extradici\u00f3n \u00a0es \u00a0un \u00a0instrumento \u00a0de cooperaci\u00f3n internacional mediante el que \u00a0los \u00a0Estados \u00a0combaten la impunidad derivada de la mera fuga de su territorio de \u00a0los \u00a0infractores \u00a0de \u00a0las \u00a0leyes, \u00a0tal \u00a0dispositivo \u00a0de asistencia y solidaridad \u00a0internacional \u00a0parte \u00a0del \u00a0supuesto de la soberan\u00eda tanto del Estado requirente \u00a0como \u00a0 del \u00a0requerido, \u00a0una \u00a0de \u00a0cuyas \u00a0manifestaciones \u00a0m\u00e1s \u00a0cl\u00e1sicas \u00a0es \u00a0la \u00a0administraci\u00f3n \u00a0de \u00a0justicia, a trav\u00e9s de la cual los Estados a trav\u00e9s de sus \u00a0Jueces \u00a0y \u00a0Magistrados \u00a0ejercen \u00a0la \u00a0soberan\u00eda \u00a0al \u00a0interior \u00a0de \u00a0su territorio \u00a0imponiendo \u00a0las \u00a0sanciones \u00a0a \u00a0que \u00a0haya \u00a0lugar o, en todo caso, resolviendo los \u00a0conflictos conforme a su juridicidad\u201d. \u00a0\u00a0<\/p>\n<p>\u201cEs \u00a0en \u00a0ese \u00a0orden \u00a0de \u00a0ideas \u00a0que \u00a0las \u00a0decisiones \u00a0jur\u00eddicas \u00a0de \u00a0un \u00a0Estado que sean necesarias para demandar de otro \u00a0Estado \u00a0la \u00a0extradici\u00f3n \u00a0de \u00a0una \u00a0persona, \u00a0son materialmente intocables y solo \u00a0pueden \u00a0ser \u00a0objeto \u00a0de \u00a0revisi\u00f3n \u00a0formal, \u00a0es \u00a0decir \u00a0con \u00a0prescindencia de su \u00a0esencialidad, \u00a0que \u00a0conforme \u00a0al \u00a0principio de buena fe, que es principio de las \u00a0relaciones internacionales, se presume legal y acertada&#8221;. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Lo \u00a0anterior \u00a0es raz\u00f3n suficiente para no reponer el auto impugnado \u00a0en \u00a0cuanto \u00a0hace \u00a0referencia \u00a0a \u00a0las \u00a0declaraciones \u00a0de \u00a0los \u00a0agentes especiales \u00a0Smallwood \u00a0y Morales, pues ciertamente lo que pretende el se\u00f1or FERRARIO es que \u00a0se examine el m\u00e9rito de ellas, cuesti\u00f3n vedada para la Corte. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Y \u00a0aunque \u00a0se afirme por el defensor, sin ninguna sustentaci\u00f3n, por \u00a0cierto, \u00a0que \u00a0las \u00a0pruebas \u00a0relacionadas \u00a0con \u00a0la \u00a0constituci\u00f3n de MULTIPIX, el \u00a0operador \u00a0telef\u00f3nico, \u00a0el \u00a0amparo \u00a0legal \u00a0de las transferencias monetarias y la \u00a0licencia \u00a0de \u00a0funcionamiento \u00a0inciden de manera directa sobre la aplicaci\u00f3n del \u00a0art\u00edculo \u00a0558 \u00a0del \u00a0estatuto procesal, no hay duda de que el prop\u00f3sito real se \u00a0dirige \u00a0tambi\u00e9n a plantear el debate sobre la responsabilidad de su poderdante, \u00a0por \u00a0lo que tambi\u00e9n sobre estos aspectos el auto cuestionado no se modificar\u00e1. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Finalmente, \u00a0respecto \u00a0de la incorporaci\u00f3n al expediente del primer \u00a0Pliego \u00a0Acusatorio en ingl\u00e9s, reclamado por ambos recurrentes, a lo dicho en la \u00a0providencia \u00a0de \u00a0junio \u00a06 \u00a0se \u00a0agrega \u00a0que el documento que definitivamente dice \u00a0aducir \u00a0el \u00a0Estado \u00a0requirente \u00a0y \u00a0con \u00a0base \u00a0en el cual se expidi\u00f3 la orden de \u00a0arresto \u00a0de \u00a0diciembre \u00a031 \u00a0de 1998 es el Segundo Pliego Acusatorio Subsiguiente \u00a0que, \u00a0conforme \u00a0a \u00a0la \u00a0declaraci\u00f3n jurada de la Fiscal Federal Auxiliar DESIREE \u00a0LABORDE \u00a0SANFIORENZO, deja sin efecto el pliego anterior y \u201cse convierte en el \u00a0documento acusatorio\u201d (fls. 113 y 114 del cuaderno No. 2). \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0No se repondr\u00e1, pues, el auto impugnado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto \u00a0la Corte Suprema de Justicia, Sala de \u00a0Casaci\u00f3n Penal, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0No \u00a0reponer \u00a0el auto de junio 6 de 2000, mediante el cual se negaron \u00a0las \u00a0peticiones \u00a0hechas \u00a0por \u00a0el \u00a0se\u00f1or \u00a0ROBERTO ANGELO FERRARIO POZZI y por su \u00a0defensor. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Notif\u00edquese y c\u00famplase. \u00a0\u00a0<\/p>\n<p>EDGAR \u00a0 \u00a0LOMBANA \u00a0TRUJILLO \u00a0\u00a0<\/p>\n<p>FERNANDO \u00a0E. \u00a0ARBOLEDA \u00a0RIPOLL \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JORGE E. CORDOBA POVEDA \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 A. \u00a0 GALVEZ \u00a0 ARGOTE \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JORGE ANIBAL GOMEZ GALLEGO \u00a0\u00a0<\/p>\n<p>MARIO \u00a0 \u00a0MANTILLA \u00a0 \u00a0NOUGUES \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 CARLOS E. MEJIA \u00a0ESCOBAR \u00a0\u00a0<\/p>\n<p>ALVARO \u00a0ORLANDO \u00a0PEREZ \u00a0PINZON \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 NILSON PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>TERESA RUIZ NU\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso N\u00ba 16107 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACION PENAL \u00a0 MAGISTRADO \u00a0PONENTE \u00a0\u00a0 ALVARO \u00a0ORLANDO \u00a0PEREZ \u00a0PINZON \u00a0\u00a0 APROBADO ACTA No. 138 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Santa \u00a0Fe \u00a0de Bogot\u00e1, D. C., quince (15) de agosto del a\u00f1o dos mil \u00a0(2000) \u00a0\u00a0 VISTOS \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Resuelve \u00a0la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3341","post","type-post","status-publish","format-standard","hentry","category-8"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/3341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=3341"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/3341\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=3341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=3341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=3341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}