{"id":31383,"date":"2023-09-13T17:38:09","date_gmt":"2023-09-13T17:38:09","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap5135-201544790\/"},"modified":"2023-09-13T17:38:09","modified_gmt":"2023-09-13T17:38:09","slug":"ap5135-201544790","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap5135-201544790\/","title":{"rendered":"AP5135-2015(44790)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>AP5135-2015 \u00a0<\/p>\n<p>Radicaci\u00f3n N\u00b0 44790 \u00a0<\/p>\n<p>(Aprobado acta N\u00ba 314)\u00a0 \u00a0<\/p>\n<p>Bogot\u00e1, D.C., nueve (9) de septiembre de dos \u00a0mil quince (2015). \u00a0\u00a0<\/p>\n<p>Procede la Sala a verificar los requisitos de \u00a0l\u00f3gica \u00a0y \u00a0debida \u00a0argumentaci\u00f3n \u00a0de la demanda de casaci\u00f3n presentada por el \u00a0defensor \u00a0de \u00a0DORIAN HEIMAR ALZATE \u00c1LVAREZ. \u00a0\u00a0<\/p>\n<p>H E C H O S \u00a0<\/p>\n<p>Fueron \u00a0 expuestos \u00a0 por \u00a0el \u00a0ad \u00a0 \u00a0 quem \u00a0 \u00a0 de \u00a0 \u00a0 la \u00a0 \u00a0siguiente \u00a0manera: \u00a0\u00a0<\/p>\n<p>\u201cHacia \u00a0las 10:10 p.m. del 9 de noviembre \u00a0de \u00a02009, a la altura del peaje La Uribe, km. 12+700 de la v\u00eda Cartago-Cali, el \u00a0cami\u00f3n \u00a0 de \u00a0placas \u00a0SOO \u00a0764, \u00a0marca \u00a0Chevrolet, \u00a0conducido \u00a0por \u00a0DORIAN \u00a0HEIMAR ALZATE \u00c1LVAREZ colision\u00f3 \u00a0contra \u00a0la motocicleta Honda de placa NVY 24B, caus\u00e1ndole graves lesiones en su \u00a0miembro inferior izquierdo al se\u00f1or Erney Saavedra Franco\u201d. \u00a0\u00a0<\/p>\n<p>A N T E C E D E N T E S \u00a0<\/p>\n<p>1. \u00a0El \u00a021 \u00a0de noviembre de 2011, ante el Juzgado Promiscuo Municipal de \u00a0Bugalagrande \u00a0 (Valle), \u00a0se \u00a0formul\u00f3 \u00a0imputaci\u00f3n \u00a0en \u00a0contra \u00a0de \u00a0DORIAN \u00a0 HEIMAR \u00a0ALZATE \u00a0\u00c1LVAREZ \u00a0por \u00a0el \u00a0delito \u00a0de \u00a0lesiones \u00a0personales \u00a0culposas (art\u00edculos 111, 112, 113, 114, 117 y \u00a0120 \u00a0del \u00a0C\u00f3digo \u00a0Penal). \u00a0El \u00a0mencionado \u00a0no acept\u00f3 los cargos, por lo que la \u00a0Fiscal\u00eda \u00a022 \u00a0Local \u00a0de \u00a0Tul\u00faa present\u00f3, el 10 de febrero de 2012, escrito de \u00a0acusaci\u00f3n.1 \u00a0\u00a0<\/p>\n<p>2. Correspondieron las diligencias al Juzgado \u00a0Promiscuo \u00a0Municipal \u00a0con \u00a0funci\u00f3n \u00a0de \u00a0conocimiento de San Pedro que, luego de \u00a0celebrar \u00a0las audiencias de formulaci\u00f3n de acusaci\u00f3n, preparatoria y el juicio \u00a0oral, \u00a0anunci\u00f3, \u00a0el \u00a029 \u00a0de octubre de 2013, sentido condenatorio del fallo, al \u00a0cual \u00a0dio lectura en la misma fecha imponiendo a ALZATE \u00a0\u00c1LVAREZ \u00a0las \u00a0penas principales de prisi\u00f3n por nueve \u00a0(9) \u00a0meses \u00a0y \u00a0dieciocho \u00a0(18) \u00a0d\u00edas, \u00a0multa de seis punto nueve (6.9) salarios \u00a0m\u00ednimos \u00a0 legales \u00a0mensuales \u00a0y \u00a0las \u00a0accesorias \u00a0de \u00a0inhabilitaci\u00f3n \u00a0para \u00a0el \u00a0ejercicio \u00a0de derechos y funciones p\u00fablicas y privaci\u00f3n del derecho a conducir \u00a0veh\u00edculos \u00a0por el t\u00e9rmino de la sanci\u00f3n privativa de la libertad, al hallarlo \u00a0autor \u00a0responsable \u00a0de la conducta punible por la que fue convocado a juicio. Le \u00a0concedi\u00f3 \u00a0la \u00a0suspensi\u00f3n \u00a0condicional de la ejecuci\u00f3n de la pena.2 \u00a0\u00a0<\/p>\n<p>3. \u00a0Apelada \u00a0esta \u00a0determinaci\u00f3n \u00a0por la defensa, fue confirmada por el \u00a0Tribunal \u00a0Superior \u00a0del Distrito Judicial de Buga -Sala Penal- el 4 de agosto de \u00a02014.3 \u00a0\u00a0<\/p>\n<p>LA DEMANDA DE CASACI\u00d3N \u00a0<\/p>\n<p>El \u00a0apoderado \u00a0del \u00a0sentenciado present\u00f3 el \u00a0recurso \u00a0 extraordinario \u00a0 para \u00a0 postular \u00a0 un \u00a0cargo \u00a0principal \u00a0y \u00a0uno subsidiario \u00a0en \u00a0contra \u00a0del \u00a0fallo \u00a0de segunda instancia, ambos al \u00a0amparo \u00a0de la causal prevista en el art\u00edculo 181, numeral 3\u00ba, de la Ley 906 de \u00a02004. \u00a0\u00a0<\/p>\n<p>En \u00a0 el \u00a0 cargo \u00a0principal, denuncia un error de hecho por falso juicio \u00a0de \u00a0existencia \u00a0por omisi\u00f3n \u00a0como \u00a0quiera \u00a0que, \u00a0asegura, \u00a0los \u00a0juzgadores de instancia no tuvieron en cuenta \u00a0cuatro \u00a0aspectos \u00a0acreditados en el tr\u00e1mite: \u201c1. La \u00a0conciencia \u00a0de \u00a0la \u00a0v\u00edctima \u00a0de \u00a0la \u00a0intenci\u00f3n de pasar (sic) al otro lado del \u00a0veh\u00edculo \u00a0del \u00a0acusado. \u00a02. \u00a0El \u00a0hecho \u00a0que \u00a0mi poderdante estaba parado cuando \u00a0(sic), \u00a0segundos \u00a0antes \u00a0del \u00a0accidente. 3. El tr\u00e1nsito del veh\u00edculo automotor \u00a0motocicleta \u00a0por \u00a0el carril izquierdo. 4. La falta de valoraci\u00f3n del testimonio \u00a0dado \u00a0por \u00a0el \u00a0acusado, \u00a0(sic) \u00a0del que carece de cualquier valoraci\u00f3n tanto en \u00a0primera como en segunda instancia\u201d. \u00a0\u00a0<\/p>\n<p>En \u00a0ese \u00a0orden, \u00a0retoma \u00a0la declaraci\u00f3n del \u00a0motociclista \u00a0involucrado \u00a0en \u00a0los hechos para destacar la forma en que se\u00f1al\u00f3 \u00a0c\u00f3mo \u00a0previo \u00a0a \u00a0la entrada del peaje de La Uribe, rumbo a Cartago, se percat\u00f3 \u00a0de \u00a0la \u00a0presencia del cami\u00f3n conducido por el acusado, obstaculizando un carril \u00a0de \u00a0la \u00a0v\u00eda, \u00a0que \u00a0se \u00a0aprestaba \u00a0a atravesar la calzada hacia una estaci\u00f3n de \u00a0servicio. \u00a0En \u00a0consecuencia, asevera, es claro que aquel estaba ejecutando dicha \u00a0maniobra \u00a0y, \u00a0no \u00a0obstante, \u00a0se \u00a0decidi\u00f3 \u00a0a \u00a0sobrepasarlo con las consecuencias \u00a0conocidas, \u00a0las \u00a0que \u00a0develan el exceso de velocidad con el que se desplazaba al \u00a0punto \u00a0que \u00a0qued\u00f3 \u00a0a m\u00e1s de 70 metros de distancia del sitio donde sucedi\u00f3 el \u00a0impacto. \u00a0En \u00a0concepto \u00a0del \u00a0casacionista, \u00a0es evidente que se hicieron se\u00f1ales \u00a0inequ\u00edvocas \u00a0al \u00a0cambio de calzada, incluido el uso de las luces direccionales, \u00a0haciendo \u00a0caso omiso la v\u00edctima de estas indicaciones por lo que debe asumir el \u00a0resultado \u00a0de \u00a0su \u00a0imprudencia, toda vez que, sostiene, el conductor del cami\u00f3n \u00a0acat\u00f3 \u00a0el \u00a0protocolo \u00a0previsto en el C\u00f3digo Nacional de Tr\u00e1nsito acerca de la \u00a0materia. \u00a0\u00a0<\/p>\n<p>De \u00a0otra \u00a0parte, \u00a0dice, \u00a0se \u00a0soslay\u00f3 que la \u00a0motocicleta \u00a0iba \u00a0por \u00a0el \u00a0lado \u00a0izquierdo \u00a0de \u00a0la \u00a0v\u00eda \u00a0cuando \u00a0las \u00a0normas de \u00a0conducci\u00f3n \u00a0ense\u00f1an \u00a0que deb\u00eda hacerlo por el lado contrario, en especial por \u00a0la \u00a0 proximidad \u00a0de \u00a0un \u00a0peaje, \u00a0entonces, \u00a0aduce, \u00a0ese \u00a0actuar \u00a0negligente \u00a0era \u00a0imprevisible \u00a0 \u00a0para \u00a0 \u00a0ALZATE \u00a0 \u00c1LVAREZ \u00a0por \u00a0lo \u00a0que \u00a0no \u00a0puede \u00a0endilg\u00e1rsele \u00a0el insuceso, sobre todo al \u00a0cobijarlo \u00a0el \u00a0principio \u00a0de confianza en virtud del cual le era v\u00e1lido esperar \u00a0de los dem\u00e1s usuarios de la carretera un transitar adecuado. \u00a0\u00a0<\/p>\n<p>Por \u00faltimo, refiere que los pronunciamientos \u00a0de \u00a0instancia \u00a0no \u00a0tuvieron en cuenta la versi\u00f3n de su prohijado quien inform\u00f3 \u00a0c\u00f3mo \u00a0suspendi\u00f3 \u00a0su \u00a0recorrido \u00a0para \u00a0ingresar \u00a0a \u00a0la estaci\u00f3n de servicio ya \u00a0mencionada \u00a0con \u00a0el fin de pernoctar, siguiendo el procedimiento correspondiente \u00a0para la maniobra. \u00a0\u00a0<\/p>\n<p>En estas condiciones, a su juicio, se obvi\u00f3 \u00a0que \u00a0la \u00a0violaci\u00f3n al deber objetivo de cuidado es atribuible a la v\u00edctima del \u00a0accidente, \u00a0no \u00a0a \u00a0su asistido, sin que existan premisas que evidencien falaz la \u00a0versi\u00f3n \u00a0que \u00a0rindi\u00f3 \u00a0acerca de lo ocurrido. Por ende, pide casar la sentencia \u00a0y, \u00a0 en \u00a0 su \u00a0 reemplazo, \u00a0 se \u00a0 absuelva \u00a0 a \u00a0 ALZATE \u00a0\u00c1LVAREZ. \u00a0\u00a0<\/p>\n<p>A \u00a0 \u00a0su \u00a0 \u00a0vez, \u00a0 en \u00a0 el \u00a0 cargo \u00a0subsidiario, \u00a0aduce la comisi\u00f3n de \u00a0un \u00a0 error \u00a0de \u00a0hecho \u00a0por \u00a0falso \u00a0raciocinio \u00a0\u201cpor \u00a0violaci\u00f3n \u00a0de \u00a0la \u00a0sana cr\u00edtica en las leyes de la ciencia y de la f\u00edsica\u201d. \u00a0Asegura \u00a0que \u00a0la \u00a0velocidad \u00a0a la que se desplazaba la \u00a0motocicleta \u00a0fue determinante \u00a0en \u00a0la \u00a0ocurrencia \u00a0del \u00a0choque, as\u00ed el Tribunal estime lo contrario, ya que el \u00a0croquis \u00a0levantado \u00a0por la polic\u00eda de carreteras indica que esta qued\u00f3 a 70.90 \u00a0metros \u00a0del \u00a0lugar \u00a0donde ocurri\u00f3 el impacto. \u201cPara \u00a0quedar \u00a0un \u00a0veh\u00edculo \u00a0a \u00a0esta \u00a0distancia \u00a0[\u2026] \u00a0es \u00a0necesario \u00a0que \u00a0la \u00a0fuerza \u00a0-din\u00e1mica- \u00a0y el movimiento -cinem\u00e1tica- que (sic) este tenga sea muy elevada, \u00a0y \u00a0que \u00a0por \u00a0ello \u00a0venga \u00a0a \u00a0una \u00a0(sic) \u00a0muy \u00a0elevada velocidad\u201d. En \u00a0 \u00a0esa \u00a0 secuencia, \u00a0 afirma, \u00a0 \u201csi \u00a0consideramos \u00a0el coeficiente de rozamiento, el cual es f\u00e1cil hacerlo pues est\u00e1 \u00a0probado \u00a0en \u00a0el proceso el modelo de la moto, una 2008, es decir con neum\u00e1ticos \u00a0nuevos, \u00a0est\u00e1 \u00a0probada \u00a0la \u00a0carretera, \u00a0las condiciones de la misma, hormig\u00f3n, \u00a0seco, \u00a0buena visibilidad, tenemos un porcentaje de rozamiento de entre 0,6-0,4 % \u00a0de \u00a00,8 m\u00e1ximo a 0,4 m\u00ednimo [\u2026] y conocida la fuerza (sic) desacertar\u00eda que \u00a0no \u00a0es \u00a0otra \u00a0que \u00a0a \u00a0constante \u00a0de \u00a0Newton, \u00a0es decir 9,8 metros por segundo al \u00a0cuadrado, \u00a0tenemos \u00a0que \u00a0la \u00a0velocidad \u00a0es \u00a0de \u00a0unos 81.71. En su conversi\u00f3n en \u00a0Km\/hora. \u00a0Velocidad \u00a0que \u00a0excede \u00a0con \u00a0(sic) \u00a0crecer \u00a0la \u00a0que deb\u00eda tener en la \u00a0carretera \u00a0donde sucedi\u00f3 el hecho y m\u00e1xime si se considera que estaba cerca de \u00a0un peaje\u201d. \u00a0\u00a0<\/p>\n<p>De este modo, pregona, es f\u00e1cil advertir que \u00a0la \u00a0velocidad \u00a0del \u00a0motociclista \u00a0lo \u00a0dejaba \u00a0a \u00a0merced \u00a0de \u00a0accidentes \u00a0como el \u00a0sucedido, \u00a0lo \u00a0que \u00a0se \u00a0corrobora, \u00a0reitera, con la distancia a la que qued\u00f3 el \u00a0veh\u00edculo \u00a0del \u00a0sitio \u00a0del \u00a0impacto, \u00a0a \u00a0lo \u00a0que \u00a0se \u00a0suma que ya es regla de la \u00a0experiencia \u00a0\u201cel hecho que esta gente (de las motos) \u00a0se conduce de la forma m\u00e1s temeraria\u201d. \u00a0\u00a0<\/p>\n<p>As\u00ed, concluye, fue la actitud de la v\u00edctima \u00a0la \u00a0que \u00a0produjo \u00a0la \u00a0colisi\u00f3n, de manera tal que si se elimina esta condici\u00f3n \u00a0necesaria \u00a0no \u00a0se \u00a0hubiese \u00a0producido \u00a0el \u00a0resultado \u00a0o, \u00a0por lo menos, habr\u00edan \u00a0concurrido \u00a0posibilidades \u00a0de \u00a0reacci\u00f3n \u00a0tendientes a evitarlo, por lo que pide \u00a0casar la sentencia y se profiera, en su lugar, fallo absolutorio. \u00a0\u00a0<\/p>\n<p>\u00a0 CONSIDERACIONES\u00a0 \u00a0DE\u00a0 LA\u00a0 CORTE \u00a0\u00a0<\/p>\n<p>1. \u00a0El \u00a0proceso penal se caracteriza por una \u00a0serie \u00a0de \u00a0etapas \u00a0concatenadas, \u00a0revestidas \u00a0de \u00a0un plexo de garant\u00edas, en las \u00a0cuales \u00a0 \u00a0se \u00a0 somete \u00a0 a \u00a0 controversia \u00a0 de \u00a0 la \u00a0 jurisdicci\u00f3n \u00a0 un \u00a0 asunto \u00a0jur\u00eddico-procesal \u00a0 cuya \u00a0 discusi\u00f3n \u00a0 culmina \u00a0con \u00a0la \u00a0sentencia, \u00a0decisi\u00f3n \u00a0susceptible \u00a0de \u00a0impugnaci\u00f3n \u00a0por \u00a0v\u00eda \u00a0de \u00a0la \u00a0apelaci\u00f3n \u00a0en \u00a0aras de que la \u00a0inconformidad \u00a0de \u00a0quien la interpone sea solventada por el superior jer\u00e1rquico \u00a0del \u00a0funcionario que la emiti\u00f3 para que \u00e9ste la confirme, modifique o revoque, \u00a0si a ello hubiere lugar. \u00a0\u00a0<\/p>\n<p>Dicho \u00a0contexto \u00a0explica \u00a0por qu\u00e9 el debate \u00a0sobre \u00a0las \u00a0aristas \u00a0de \u00a0inter\u00e9s \u00a0para el ejercicio de la acci\u00f3n penal cesa en \u00a0tales \u00a0escenarios, \u00a0es decir, durante el decurso de las instancias, previ\u00e9ndose \u00a0la \u00a0existencia \u00a0de un recurso extraordinario, la casaci\u00f3n, solamente cuando por \u00a0espec\u00edficas \u00a0causales, \u00a0en \u00a0este \u00a0caso \u00a0las \u00a0del art\u00edculo 181 de la Ley 906 de \u00a02004, \u00a0se pretenda un estudio respecto de la legalidad del fallo por parte de la \u00a0Corte \u00a0Suprema \u00a0de Justicia. No se trata, entonces, de prolongar la controversia \u00a0que \u00a0feneci\u00f3 \u00a0con \u00a0la \u00a0emisi\u00f3n \u00a0de \u00a0una \u00a0providencia \u00a0amparada \u00a0con \u00a0la \u00a0doble \u00a0presunci\u00f3n de acierto y legalidad. \u00a0\u00a0<\/p>\n<p>Por ende, existen par\u00e1metros que hacen de la \u00a0demanda \u00a0un \u00a0escrito \u00a0sometido a estrictas y espec\u00edficas reglas de postulaci\u00f3n \u00a0que \u00a0bajo \u00a0la \u00e9gida de principios como el de autonom\u00eda, limitaci\u00f3n, claridad, \u00a0entre \u00a0otros, \u00a0debe \u00a0bastarse a s\u00ed mismo para demostrar el yerro planteado y su \u00a0trascendencia, \u00a0 siendo \u00a0premisa \u00a0fundamental \u00a0que \u00a0la \u00a0simple \u00a0discrepancia \u00a0de \u00a0criterios \u00a0no \u00a0constituye \u00a0una \u00a0variable \u00a0con la viabilidad de ser auscultada en \u00a0esta \u00a0sede \u00a0extraordinaria (Cfr. CSJ AP, 18 Ago 2010, \u00a0Rad. 33559). \u00a0\u00a0<\/p>\n<p>\u00a0 2. Lo anterior se menciona por cuanto \u00a0ninguno \u00a0de estos aspectos l\u00f3gico-conceptuales fueron observados por el censor, \u00a0ya \u00a0que \u00fanicamente plasm\u00f3 en su libelo la postura subjetiva que le merecen las \u00a0pruebas \u00a0aportadas \u00a0a \u00a0la actuaci\u00f3n, diversa a la de la judicatura, pasando por \u00a0alto \u00a0que \u00a0esa \u00a0llana divergencia es insuficiente para derruir la presunci\u00f3n de \u00a0legalidad de la sentencia atacada. V\u00e9ase: \u00a0\u00a0<\/p>\n<p>2.1. Al denunciarse \u00a0un \u00a0falso \u00a0juicio de existencia por omisi\u00f3n no basta con aludir que el juzgador \u00a0excluy\u00f3 \u00a0un \u00a0espec\u00edfico medio probatorio, porque lo relevante es demostrar que \u00a0incurri\u00f3 \u00a0en \u00a0omisi\u00f3n \u00a0absoluta, \u00a0es decir, que el contenido material de una o \u00a0varias \u00a0pruebas \u00a0no \u00a0fue considerado de ninguna forma en el ejercicio valorativo \u00a0del \u00a0funcionario \u00a0judicial \u00a0a \u00a0pesar de contar con la capacidad de desvirtuar el \u00a0sentido \u00a0del \u00a0fallo, \u00a0para \u00a0lo \u00a0cual \u00a0el casacionista debe proponer un an\u00e1lisis \u00a0eficaz \u00a0que, \u00a0incluyendo la apreciaci\u00f3n de los elementos de convicci\u00f3n que s\u00ed \u00a0fueron \u00a0tenidos \u00a0en cuenta, sin ninguna dificultad, lleve a colegir la presencia \u00a0de tal situaci\u00f3n. \u00a0\u00a0<\/p>\n<p>En este asunto el demandante, en un discurso \u00a0de \u00a0libre \u00a0elaboraci\u00f3n, \u00a0no \u00a0se \u00a0remite \u00a0en \u00a0estricto sentido a cotejar en qu\u00e9 \u00a0consisti\u00f3 \u00a0 la \u00a0 exclusi\u00f3n \u00a0 probatoria \u00a0 que \u00a0 alega \u00a0sino \u00a0que \u00a0reprocha \u00a0la \u00a0pretermisi\u00f3n \u00a0de \u00a0ciertas \u00a0conclusiones \u00a0suasorias \u00a0que depreca favorables a su \u00a0asistido, \u00a0confundiendo \u00a0as\u00ed \u00a0la \u00a0prueba, con lo probado, a pesar de constituir \u00a0fases \u00a0distintas \u00a0de \u00a0aproximaci\u00f3n \u00a0a \u00a0la \u00a0formaci\u00f3n \u00a0del conocimiento. En ese \u00a0orden, \u00a0no \u00a0puede \u00a0aducir \u00a0que \u00a0el \u00a0contenido \u00a0literal propio de la modalidad de \u00a0infracci\u00f3n \u00a0a \u00a0la \u00a0que \u00a0acude \u00a0no \u00a0fue \u00a0objeto \u00a0de \u00a0examen \u00a0por el ad \u00a0quem, pues al constatar el prove\u00eddo \u00a0cuestionado se avizora un panorama diferente al que proclama: \u00a0\u00a0<\/p>\n<p>\u201cEl \u00a0informe \u00a0policial \u00a0de \u00a0accidente \u00a0de \u00a0tr\u00e1nsito \u00a0incorporado \u00a0a \u00a0la \u00a0actuaci\u00f3n \u00a0como \u00a0evidencia \u00a0#6, \u00a0de manera clara \u00a0muestra \u00a0la \u00a0forma \u00a0como \u00a0el cami\u00f3n conducido por el acusado se atraves\u00f3 en el \u00a0carril \u00a0izquierdo \u00a0por donde transitaba la motocicleta conducida por la v\u00edctima \u00a0para \u00a0adelantar el cami\u00f3n, que previamente a su maniobra de giro a la izquierda \u00a0se \u00a0encontraba \u00a0detenido \u00a0sobre \u00a0la \u00a0parte \u00a0derecha \u00a0de \u00a0la v\u00eda, situaci\u00f3n que \u00a0oblig\u00f3 \u00a0al \u00a0motociclista \u00a0a \u00a0adelantar \u00a0al \u00a0cami\u00f3n \u00a0por \u00a0el \u00a0carril libre a la \u00a0izquierda, \u00a0conforme \u00a0lo \u00a0precept\u00faa \u00a0el \u00a0art\u00edculo \u00a094 \u00a0del C\u00f3digo Nacional de \u00a0Tr\u00e1nsito -CNT. \u00a0\u00a0<\/p>\n<p>En \u00a0estas \u00a0condiciones, \u00a0no tiene raz\u00f3n el \u00a0apelante \u00a0cuando \u00a0atribuye \u00a0el \u00a0accidente \u00a0a \u00a0la \u00a0maniobra \u00a0del \u00a0motociclista de \u00a0adelantar \u00a0el \u00a0cami\u00f3n \u00a0por \u00a0la \u00a0izquierda, por cuanto en las condiciones en que \u00a0estaba \u00a0el \u00a0cami\u00f3n, estacionado a la derecha de la v\u00eda, el motociclista deb\u00eda \u00a0sobrepasarlo \u00a0por \u00a0el \u00a0carril \u00a0libre \u00a0a \u00a0la \u00a0izquierda \u00a0y no por la derecha como \u00a0postula \u00a0el \u00a0apelante, \u00a0pues \u00a0de \u00a0haberlo \u00a0hecho \u00a0de \u00a0esa manera el motociclista \u00a0habr\u00eda \u00a0incurrido \u00a0en \u00a0violaci\u00f3n \u00a0del \u00a0reglamento, \u00a0concretamente \u00a0de la norma \u00a0establecida \u00a0a \u00a0los efectos de adelantamiento de otro veh\u00edculo en el mencionado \u00a0art\u00edculo 94 del CNT. \u00a0\u00a0<\/p>\n<p>[\u2026] \u00a0Adem\u00e1s \u00a0el \u00a0propio \u00a0acusado en su \u00a0testimonio \u00a0asevera \u00a0que \u00a0el \u00a0sitio \u00a0es \u00a0una \u00a0v\u00eda \u00a0de dos carriles y se permite \u00a0adelantar \u00a0por la izquierda, y que por su parte se inclin\u00f3 al lado izquierdo de \u00a0la \u00a0v\u00eda para ingresar a la bomba Distracom, pero el motociclista que iba a alta \u00a0velocidad \u00a0le \u00a0dio \u00a0al \u00a0retrovisor \u00a0de \u00a0la Turbo. [\u2026] A su turno, el lesionado \u00a0Saavedra \u00a0Franco \u00a0explica \u00a0que \u00a0procedi\u00f3 \u00a0a \u00a0adelantar el cami\u00f3n por el carril \u00a0izquierdo \u00a0porque \u00a0estaba \u00a0obstaculizando el carril derecho, pero en ese momento \u00a0ese \u00a0veh\u00edculo \u00a0arranc\u00f3 \u00a0y \u00a0lo \u00a0impact\u00f3 \u00a0en \u00a0el lado derecho de la motocicleta \u00a0[\u2026] \u00a0\u00a0<\/p>\n<p>La \u00a0actuaci\u00f3n \u00a0demuestra \u00a0que \u00a0el \u00a0acusado \u00a0ALZATE \u00a0 \u00c1LVAREZ \u00a0en \u00a0su \u00a0prop\u00f3sito \u00a0de \u00a0ingresar \u00a0a la bomba Distracom se detuvo sobre el carril derecho \u00a0por \u00a0el \u00a0que transitaba, con lo cual obstaculiz\u00f3 el paso al motociclista que lo \u00a0suced\u00eda \u00a0 en \u00a0el \u00a0uso \u00a0de \u00a0la \u00a0v\u00eda \u00a0como \u00a0lo \u00a0resalta \u00a0el \u00a0lesionado \u00a0Saavedra \u00a0Franco. \u00a0\u00a0<\/p>\n<p>Ante esta situaci\u00f3n, el motociclista opt\u00f3 \u00a0por \u00a0ocupar \u00a0el \u00a0carril \u00a0libre \u00a0de la izquierda para adelantar el cami\u00f3n y para \u00a0ello \u00a0acompa\u00f1\u00f3 \u00a0su \u00a0acci\u00f3n \u00a0de la utilizaci\u00f3n del pito, se\u00f1al sonora que el \u00a0conductor \u00a0del \u00a0cami\u00f3n, \u00a0el \u00a0aqu\u00ed \u00a0acusado, \u00a0no \u00a0acat\u00f3, \u00a0sino \u00a0que \u00a0de manera \u00a0temeraria \u00a0y \u00a0con \u00a0violaci\u00f3n \u00a0del \u00a0reglamento, \u00a0decidi\u00f3 \u00a0arrancar \u00a0el \u00a0cami\u00f3n \u00a0gir\u00e1ndolo \u00a0 hacia \u00a0la \u00a0izquierda, \u00a0momento \u00a0en \u00a0el \u00a0cual \u00a0motociclista \u00a0que \u00a0ya \u00a0sobrepasaba \u00a0el \u00a0cami\u00f3n recibi\u00f3 el impacto en la parte derecha de su velomotor \u00a0con \u00a0el \u00a0retrovisor \u00a0izquierdo \u00a0del furg\u00f3n, que en tales condiciones adem\u00e1s de \u00a0invadirle \u00a0el \u00a0carril \u00a0de \u00a0sobrepaso \u00a0en \u00a0el \u00a0que \u00a0con \u00a0prelaci\u00f3n transitaba el \u00a0motociclista, \u00a0tambi\u00e9n \u00a0lo \u00a0golpe\u00f3 \u00a0y \u00a0con \u00a0ello \u00a0lo lanz\u00f3 para que impactara \u00a0finalmente \u00a0contra \u00a0el \u00a0tractocami\u00f3n \u00a0que se encontraba estacionado en la parte \u00a0izquierda \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0v\u00eda \u00a0 \u00a0 \u00a0[\u2026].4 \u00a0\u00a0<\/p>\n<p>De esta forma, se tiene que el cargo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0principal \u00a0parte \u00a0de par\u00e1metros errados \u00a0en \u00a0cuanto \u00a0a \u00a0la \u00a0l\u00f3gica \u00a0que ha de orientar la denuncia de un falso juicio de \u00a0existencia \u00a0por \u00a0omisi\u00f3n, toda vez que los contenidos probatorios presuntamente \u00a0excluidos \u00a0s\u00ed fueron considerados por el Tribunal, tambi\u00e9n por el a \u00a0quo \u00a0en \u00a0decisi\u00f3n que constituye una \u00a0unidad \u00a0jur\u00eddica \u00a0inescindible, \u00a0fund\u00e1ndose \u00a0el \u00a0aparente \u00a0vicio \u00a0en el efecto \u00a0demostrativo \u00a0conferido \u00a0a \u00a0los mismos y que resulta disonante al esbozado en la \u00a0demanda. \u00a0\u00a0<\/p>\n<p>As\u00ed, \u00a0se \u00a0vislumbra \u00a0que \u00a0el \u00a0libelista se \u00a0encarga \u00a0de \u00a0criticar las reflexiones de la judicatura pero no acredita en ellas \u00a0un \u00a0error fehaciente, sustentando su postura en el particular discernimiento que \u00a0tiene \u00a0del \u00a0asunto \u00a0para \u00a0desechar \u00a0la \u00a0imprudencia \u00a0de \u00a0su \u00a0prohijado \u00a0como \u00a0la \u00a0responsable \u00a0de \u00a0la colisi\u00f3n, a la manera de un alegato de instancia, en simple \u00a0contrav\u00eda \u00a0a \u00a0un pronunciamiento cobijado con la doble presunci\u00f3n de acierto y \u00a0legalidad. \u00a0\u00a0<\/p>\n<p>2.2. \u00a0Este \u00a0equ\u00edvoco \u00a0entendimiento \u00a0del \u00a0recurso \u00a0 extraordinario \u00a0 lo \u00a0replica \u00a0en \u00a0el \u00a0cargo \u00a0subsidiario, \u00a0al \u00a0evocar la comisi\u00f3n de un falso raciocinio por no atribuirse el \u00a0hipot\u00e9tico \u00a0exceso \u00a0de \u00a0velocidad \u00a0del motociclista como la causa eficiente del \u00a0accidente \u00a0-tesis elucubrada de forma confusa y con precario soporte cient\u00edfico \u00a0m\u00e1s \u00a0all\u00e1 de la arbitrariedad-, desconociendo que el juzgador de segundo grado \u00a0descart\u00f3 \u00a0el \u00a0asidero \u00a0de tal premisa al reconstruir el entorno en que ocurri\u00f3 \u00a0el \u00a0 choque, \u00a0 advirtiendo \u00a0 indiferente \u00a0la \u00a0potencial \u00a0concurrencia \u00a0de \u00a0dicha \u00a0circunstancia \u00a0por la inusitada maniobra del conductor del cami\u00f3n quien, con su \u00a0proceder \u00a0negligente, \u00a0hizo \u00a0inminente \u00a0la \u00a0producci\u00f3n \u00a0del \u00a0resultado \u00a0lesivo: \u00a0\u00a0<\/p>\n<p>\u201cDe ah\u00ed que las expresiones del procesado \u00a0diciendo \u00a0que \u00a0el \u00a0motociclista \u00a0iba \u00a0a \u00a0exceso \u00a0de \u00a0velocidad \u00a0no \u00a0sea la causa \u00a0determinante \u00a0del \u00a0accidente, \u00a0sino \u00a0el \u00a0giro \u00a0a \u00a0la \u00a0izquierda \u00a0e \u00a0invasi\u00f3n \u00a0y \u00a0atravesamiento \u00a0del \u00a0cami\u00f3n \u00a0sobre \u00a0el \u00a0carril \u00a0izquierdo \u00a0de \u00a0adelantamiento y \u00a0aceleraci\u00f3n \u00a0 \u00a0 protagonizado \u00a0 \u00a0 por \u00a0 \u00a0el \u00a0 \u00a0aqu\u00ed \u00a0 \u00a0acusado \u00a0 \u00a0ALZATE \u00a0 \u00c1LVAREZ, \u00a0quien \u00a0de \u00a0no \u00a0haber \u00a0obrado \u00a0de \u00a0esa \u00a0manera \u00a0sino \u00a0de \u00a0la forma prudente y cuidadosa que su labor de \u00a0conducci\u00f3n \u00a0 automovil\u00edstica \u00a0le \u00a0exig\u00eda, \u00a0habr\u00eda \u00a0permitido, \u00a0esto \u00a0es, \u00a0no \u00a0obstaculizado \u00a0ni \u00a0atravesado, \u00a0el \u00a0paso \u00a0del \u00a0motociclista quien a su velocidad \u00a0habr\u00eda \u00a0adelantado \u00a0el cami\u00f3n sin sufrir da\u00f1o (sic) ninguno ni impacto alguno \u00a0contra \u00a0 \u00a0el \u00a0 \u00a0furg\u00f3n \u00a0 \u00a0conducido \u00a0 \u00a0temerariamente \u00a0 \u00a0por \u00a0 \u00a0el \u00a0 \u00a0procesado \u00a0[\u2026]\u201d.5 \u00a0\u00a0<\/p>\n<p>Por \u00a0consiguiente, se denota que en lugar de \u00a0acreditarse \u00a0consistentemente \u00a0la \u00a0presencia \u00a0del yerro invocado y ense\u00f1arse su \u00a0eventual \u00a0magnitud \u00a0para \u00a0desquiciar la l\u00f3gica del fallo atacado, se aborda una \u00a0mera \u00a0discrepancia \u00a0acerca \u00a0del \u00a0m\u00e9rito \u00a0suasorio consignado en el prove\u00eddo de \u00a0segundo \u00a0grado \u00a0como \u00a0si \u00a0fuese \u00a0la Corte una instancia propicia para dirimir la \u00a0divergencia \u00a0de \u00a0pareceres, \u00a0m\u00e9todo \u00a0por \u00a0completo \u00a0refractario \u00a0a \u00a0esta \u00a0sede. \u00a0\u00a0<\/p>\n<p>Muestra \u00a0palpable \u00a0de esa errada percepci\u00f3n \u00a0que \u00a0se \u00a0tiene \u00a0del instituto, es la m\u00e1xima de la experiencia confeccionada por \u00a0el \u00a0recurrente en el sentido que es sabido \u201cel hecho \u00a0que \u00a0esta \u00a0gente \u00a0(de \u00a0las \u00a0motos) \u00a0se \u00a0conduce \u00a0de \u00a0la forma m\u00e1s temeraria\u201d, \u00a0ya que tal postulaci\u00f3n lejos de exhibirse vinculada a \u00a0un \u00a0contexto \u00a0universal, \u00a0general, \u00a0con \u00a0vocaci\u00f3n \u00a0de permanencia en el tiempo, \u00a0notorio \u00a0y \u00a0con \u00a0criterios de validez y facticidad susceptibles de verificaci\u00f3n \u00a0en \u00a0un \u00a0espacio \u00a0socio \u00a0hist\u00f3rico \u00a0determinado, \u00a0se \u00a0ofrece \u00a0constitutiva de un \u00a0silogismo \u00a0que \u00a0no supera la llana opini\u00f3n subjetiva respecto al comportamiento \u00a0que, \u00a0en sentir del demandante, asumen los motociclistas de manera permanente al \u00a0arriesgar \u00a0su \u00a0vida \u00a0en este tipo de veh\u00edculos, sin que tenga cabida, desde esa \u00a0\u00f3ptica, \u00a0un \u00a0examen \u00a0puntual \u00a0de \u00a0su actuar concreto vi\u00e9ndose compelidos a las \u00a0consecuencias \u00a0que \u00a0se \u00a0originen \u00a0en caso de verse inmersos en cualquier tipo de \u00a0accidente. \u00a0Calificativos \u00a0que \u00a0no se acompasan con el substrato conceptual que, \u00a0seg\u00fan \u00a0 se \u00a0 anot\u00f3, \u00a0caracteriza \u00a0a \u00a0aquellas \u00a0pautas \u00a0del \u00a0acontecer \u00a0humano. \u00a0\u00a0<\/p>\n<p>3. Recapitulando, el libelo no desarrolla en \u00a0debida \u00a0forma \u00a0los cargos que plantea porque no se advierte un an\u00e1lisis l\u00f3gico \u00a0argumentativo \u00a0que los soporte adecuadamente, al circunscribirse los reproches a \u00a0diatribas \u00a0parcializadas \u00a0acerca \u00a0del \u00a0modo en que los juzgadores apreciaron las \u00a0pruebas \u00a0recaudadas en las diligencias, sin demostrarse errores trascendentes en \u00a0tal \u00a0valoraci\u00f3n. \u00a0El \u00a0recurrente \u00a0pasa \u00a0por \u00a0alto \u00a0que \u00a0no \u00a0es \u00a0la casaci\u00f3n un \u00a0escenario \u00a0adecuado \u00a0para \u00a0plantear \u00a0hip\u00f3tesis \u00a0probatorias \u00a0o \u00a0recabar \u00a0en las \u00a0desechadas \u00a0por \u00a0la \u00a0judicatura \u00a0durante \u00a0el \u00a0transcurso de las instancias, como \u00a0aqu\u00ed \u00a0ocurri\u00f3, toda vez que, se recalca, no se trata \u00a0de \u00a0continuar \u00a0el \u00a0debate \u00a0f\u00e1ctico \u00a0y \u00a0jur\u00eddico que \u00a0culmin\u00f3 con la sentencia de segundo grado.\u00a0 \u00a0\u00a0<\/p>\n<p>Por \u00a0ende, \u00a0al carecer la demanda presentada \u00a0del \u00a0 \u00a0 \u00a0sustento \u00a0 \u00a0 propio \u00a0 \u00a0 de \u00a0 \u00a0 esta \u00a0 \u00a0 sede \u00a0 \u00a0 ser\u00e1 \u00a0 \u00a0 inadmitida, adem\u00e1s porque del estudio del \u00a0expediente \u00a0no \u00a0se \u00a0observa violaci\u00f3n de derechos fundamentales o garant\u00edas de \u00a0los \u00a0sujetos \u00a0procesales \u00a0en \u00a0condiciones \u00a0tales \u00a0que \u00a0sea necesario superar sus \u00a0defectos \u00a0en \u00a0orden \u00a0a una determinaci\u00f3n de fondo, ni se percibe de su contexto \u00a0que \u00a0se \u00a0precise \u00a0de \u00a0un \u00a0fallo \u00a0para \u00a0cumplir con alguna de las finalidades del \u00a0recurso (art\u00edculo 184 de la Ley 906 de 2004). \u00a0\u00a0<\/p>\n<p>4. \u00a0Por \u00a0\u00faltimo, \u00a0valga recordar que contra \u00a0esta \u00a0providencia \u00a0procede \u00a0el \u00a0mecanismo \u00a0de \u00a0insistencia, \u00a0de \u00a0acuerdo con los \u00a0lineamientos \u00a0se\u00f1alados \u00a0en el auto de 12 de diciembre de 2005, proferido en el \u00a0radicado 24322. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0 m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0la \u00a0CORTE \u00a0SUPREMA \u00a0 \u00a0 DE \u00a0 \u00a0 JUSTICIA, \u00a0 \u00a0 SALA \u00a0 \u00a0 DE \u00a0 \u00a0 CASACI\u00d3N \u00a0 \u00a0 PENAL, \u00a0\u00a0<\/p>\n<p>R \u00a0 E \u00a0 S \u00a0U \u00a0E \u00a0L \u00a0V \u00a0E \u00a0\u00a0<\/p>\n<p>INADMITIR \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0por el defensor de \u00a0DORIAN \u00a0 \u00a0HEIMAR \u00a0 \u00a0ALZATE \u00a0 \u00a0\u00c1LVAREZ. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Contra \u00a0 \u00a0 esta \u00a0 \u00a0 decisi\u00f3n \u00a0 \u00a0 procede \u00a0 \u00a0 el \u00a0 \u00a0 mecanismo \u00a0 \u00a0de \u00a0insistencia \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0 \u00a0 \u00a0comun\u00edquese \u00a0 \u00a0 \u00a0y \u00a0c\u00famplase \u00a0\u00a0<\/p>\n<p>JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>Presidente \u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0<\/p>\n<p>FERNANDO ALBERTO CASTRO CABALLERO \u00a0<\/p>\n<p>EUGENIO FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>GUSTAVO ENRIQUE MALO FERN\u00c1NDEZ \u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>PATRICIA SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 \u00a0Folio 2 carpeta actuaci\u00f3n \u00a0\u00a0<\/p>\n<p>2 \u00a0Fl. 138 c.a \u00a0\u00a0<\/p>\n<p>3 \u00a0Fl. 176 c.a \u00a0\u00a0<\/p>\n<p>4 \u00a0Cfr. \u00a0Fl. \u00a011 y s.s sentencia segunda instancia \/ Fl. \u00a0186 y s.s c.a \u00a0\u00a0<\/p>\n<p>5Cfr. \u00a0Fl. \u00a015 \u00a0y \u00a0s.s \u00a0sentencia \u00a0segunda \u00a0instancia \u00a0\/ \u00a0Fl. 190 y s.s c.a \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0 Magistrado Ponente \u00a0 AP5135-2015 \u00a0 Radicaci\u00f3n N\u00b0 44790 \u00a0 (Aprobado acta N\u00ba 314)\u00a0 \u00a0 Bogot\u00e1, D.C., nueve (9) de septiembre de dos \u00a0mil quince (2015). \u00a0\u00a0 Procede la Sala a verificar los requisitos de \u00a0l\u00f3gica \u00a0y \u00a0debida \u00a0argumentaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-31383","post","type-post","status-publish","format-standard","hentry","category-23"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/31383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=31383"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/31383\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=31383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=31383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=31383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}