{"id":31199,"date":"2023-09-13T17:37:49","date_gmt":"2023-09-13T17:37:49","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap4404-201545999\/"},"modified":"2023-09-13T17:37:49","modified_gmt":"2023-09-13T17:37:49","slug":"ap4404-201545999","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap4404-201545999\/","title":{"rendered":"AP4404-2015(45999)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>AP4404-2015 \u00a0<\/p>\n<p>Rad. 45999 \u00a0<\/p>\n<p>Aprobado Acta No. 271 \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D.C.,\u00a0 \u00a0cinco (5) de agosto de \u00a0dos mil quince (2015). \u00a0\u00a0<\/p>\n<p>ASUNTO: \u00a0<\/p>\n<p>La \u00a0Corte decide si admite o no la demanda de \u00a0casaci\u00f3n \u00a0formulada \u00a0por \u00a0el \u00a0defensor del teniente del Ej\u00e9rcito Nacional JUAN \u00a0CARLOS \u00a0SARMIENTO ROJAS, en contra de la sentencia del 30 de septiembre de 2014, \u00a0a \u00a0trav\u00e9s \u00a0de \u00a0la \u00a0cual \u00a0la \u00a0Sala \u00a0Penal \u00a0del \u00a0Tribunal \u00a0Superior de Monter\u00eda, \u00a0confirm\u00f3 \u00a0 el \u00a0 fallo \u00a0 emitido \u00a0por \u00a0el \u00a0Juzgado \u00a0Promiscuo \u00a0del \u00a0Circuito \u00a0de \u00a0Montel\u00edbano \u00a0(C\u00f3rdoba), que lo conden\u00f3 como coautor responsable del delito de \u00a0homicidio en persona protegida. \u00a0\u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a020 \u00a0de junio de 2007, en el sector de Carroquemao, jurisdicci\u00f3n \u00a0del \u00a0corregimiento \u00a0Juan \u00a0Jos\u00e9, \u00a0municipio \u00a0de \u00a0Puerto \u00a0Libertador \u00a0(C\u00f3rdoba), \u00a0aproximadamente \u00a0a \u00a0las 9 de la noche, H\u00e9ctor Espinosa Moreno, Hern\u00e1n Espinosa \u00a0Rodr\u00edguez \u00a0y Edinson \u00c1lzate Pulgar\u00edn, fueron muertos por proyectil de arma de \u00a0fuego, \u00a0en \u00a0operaci\u00f3n \u00a0militar de combate simulada denominada \u201cJerarca 10\u201d, \u00a0por \u00a0la \u00a0compa\u00f1\u00eda \u00a0Depredadora, \u00a0adscrita \u00a0al Batall\u00f3n Contraguerrilla No. 10 \u00a0\u201cGeneral \u00a0Uribe \u00a0Uribe\u201d \u00a0del \u00a0Ej\u00e9rcito Nacional, al mando del teniente JUAN \u00a0CARLOS SARMIENTO ROJAS. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>1. \u00a0El 25 de septiembre de 2008, la Fiscal\u00eda \u00a035 \u00a0 Especializada \u00a0 de \u00a0la \u00a0Unidad \u00a0Nacional \u00a0de \u00a0derechos \u00a0humanos \u00a0y \u00a0derecho \u00a0internacional \u00a0humanitario \u00a0decret\u00f3 \u00a0la \u00a0apertura de instrucci\u00f3n en contra del \u00a0teniente \u00a0JUAN \u00a0CARLOS \u00a0SARMIENTO \u00a0ROJAS, por la posible comisi\u00f3n del delito de \u00a0homicidio \u00a0en \u00a0persona \u00a0protegida, \u00a0a la cual lo vincul\u00f3 mediante diligencia de \u00a0indagatoria el 16 de octubre siguiente. \u00a0\u00a0<\/p>\n<p>2. \u00a0El \u00a024 \u00a0de \u00a0abril \u00a0de \u00a02009 \u00a0la Fiscal\u00eda \u00a0calific\u00f3 \u00a0el \u00a0m\u00e9rito \u00a0del \u00a0sumario con resoluci\u00f3n de acusaci\u00f3n en contra del \u00a0implicado, \u00a0en \u00a0calidad \u00a0de \u00a0coautor \u00a0del \u00a0concurso \u00a0de \u00a0delitos de homicidio en \u00a0persona protegida. \u00a0\u00a0<\/p>\n<p>3. \u00a0Culminada \u00a0la \u00a0etapa \u00a0de \u00a0juzgamiento, el \u00a0Juzgado \u00a0Promiscuo del Circuito de Montel\u00edbano, el 16 de mayo de 2011, conden\u00f3 \u00a0al \u00a0acusado a la pena principal de 378 meses de prisi\u00f3n, multa de 2600 salarios \u00a0m\u00ednimos \u00a0legales \u00a0mensuales \u00a0vigentes e inhabilitaci\u00f3n de derechos y funciones \u00a0p\u00fablicas \u00a0por \u00a020 \u00a0a\u00f1os, \u00a0como \u00a0coautor \u00a0del \u00a0delito \u00a0de \u00a0homicidio en persona \u00a0protegida. \u00a0\u00a0<\/p>\n<p>4. Apelada tal determinaci\u00f3n por la defensa, \u00a0la \u00a0Sala \u00a0Penal \u00a0del \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Monter\u00eda, \u00a0en prove\u00eddo del 30 de \u00a0septiembre de 2014, le imparti\u00f3 confirmaci\u00f3n. \u00a0\u00a0<\/p>\n<p>LA DEMANDA: \u00a0<\/p>\n<p>La defensa, al considerar que a su prohijado \u00a0le \u00a0fueron vulnerados los principios de presunci\u00f3n de inocencia y legalidad, al \u00a0igual \u00a0que \u00a0el \u00a0derecho fundamental del debido proceso, formul\u00f3 en contra de la \u00a0sentencia \u00a0de \u00a0segundo \u00a0grado cinco cargos, todos al amparo de la causal primera \u00a0del \u00a0art\u00edculo \u00a0207 \u00a0de \u00a0la \u00a0Ley 600 de 2000, por violaci\u00f3n indirecta de la ley \u00a0sustancial, as\u00ed: \u00a0\u00a0<\/p>\n<p>1. \u00a0Por \u00a0error de hecho consistente en falso \u00a0juicio \u00a0 de \u00a0 identidad \u00a0al \u00a0momento \u00a0de \u00a0otorgarle \u00a0m\u00e9rito \u00a0persuasivo \u00a0a \u00a0las \u00a0declaraciones \u00a0de \u00a0Wilson de Jes\u00fas Chica Monsalve y Flor del Rosario Hern\u00e1ndez \u00a0Mart\u00ednez, \u00a0que \u00a0conllev\u00f3 \u00a0a \u00a0la \u00a0falta \u00a0de \u00a0aplicaci\u00f3n \u00a0de la garant\u00eda de la \u00a0presunci\u00f3n \u00a0de \u00a0inocencia \u00a0e indebida aplicaci\u00f3n del art\u00edculo 135 del C\u00f3digo \u00a0Penal. \u00a0\u00a0<\/p>\n<p>El \u00a0Tribunal \u00a0otorg\u00f3 \u00a0un err\u00f3neo alcance a \u00a0tales \u00a0testificaciones \u00a0para \u00a0desvirtuar \u00a0la existencia de un combate leg\u00edtimo, \u00a0pese \u00a0a \u00a0que \u00a0ninguno de ellos prueba la ocurrencia de un \u201cfalso positivo\u201d y \u00a0menos \u00a0la responsabilidad de su representado. En dichas exposiciones se se\u00f1al\u00f3 \u00a0que \u00a0las v\u00edctimas, d\u00edas antes de su muerte, se encontraban en el corregimiento \u00a0de \u00a0Juan \u00a0Jos\u00e9 \u00a0y \u00a0se \u00a0hospedaban en la residencia \u201cLa Palmera\u201d, lo cual no \u00a0descartaba \u00a0la \u00a0intenci\u00f3n \u00a0de los occisos de delinquir o su no pertenencia a un \u00a0grupo \u00a0armado; por el contrario, generaban la sospecha sobre los motivos por los \u00a0cuales \u00a0tres \u00a0hombres \u00a0j\u00f3venes y solteros se alojaban en una zona de comprobada \u00a0presencia \u00a0guerrillera \u00a0y de bandas criminales, sin actividad laboral conocida y \u00a0portando \u00a0armas \u00a0de \u00a0fuego, \u00a0m\u00e1xime cuando de la testificaci\u00f3n de Wilson Chica \u00a0Monsalve \u00a0se \u00a0ten\u00eda \u00a0conocimiento \u00a0que \u00a0se \u00a0dedicaban a actividades delictivas. \u00a0\u00a0<\/p>\n<p>De igual manera, del relato de Chica se tiene \u00a0que \u00a0junto \u00a0con \u00a0sus \u00a0amigos \u00a0se \u00a0hab\u00eda \u00a0concertado \u00a0con \u00a0algunos \u00a0miembros del \u00a0Ej\u00e9rcito \u00a0Nacional \u00a0para \u00a0la \u00a0ejecuci\u00f3n \u00a0de conductas il\u00edcitas, de lo cual se \u00a0sirvi\u00f3 \u00a0el \u00a0juzgador \u00a0para \u00a0vincular \u00a0a \u00a0integrantes \u00a0de esta instituci\u00f3n a la \u00a0actuaci\u00f3n \u00a0sin \u00a0que \u00a0se \u00a0demostrara \u00a0en \u00a0concreto \u00a0si \u00a0dicho acuerdo fue con el \u00a0sentenciado, \u00a0quien adem\u00e1s se encontraba a m\u00e1s de 10 kil\u00f3metros del sitio del \u00a0suceso. \u00a0Adicionalmente, \u00a0no se le puede tener como testigo presencial de \u00e9ste, \u00a0ya \u00a0que no estuvo en la supuesta ejecuci\u00f3n ni brind\u00f3 nombre o una descripci\u00f3n \u00a0f\u00edsica de los pretendidos autores del il\u00edcito. \u00a0\u00a0<\/p>\n<p>De \u00a0ah\u00ed \u00a0que \u00a0no \u00a0se \u00a0sabe \u00a0por \u00a0qu\u00e9 \u00a0los \u00a0sentenciadores \u00a0concluyeron \u00a0que \u00a0JUAN CARLOS SARMIENTO ROJAS tuvo relaci\u00f3n con \u00a0lo \u00a0sucedido, \u00a0as\u00ed \u00a0como \u00a0las \u00a0dem\u00e1s \u00a0personas \u00a0que \u00a0fueron sentenciadas en un \u00a0proceso \u00a0paralelo, \u00a0en tanto las declaraciones mencionadas no demuestran (i) que \u00a0no \u00a0haya \u00a0habido \u00a0combate; \u00a0(ii) la comisi\u00f3n del delito de homicidio en persona \u00a0protegida; \u00a0(iii) \u00a0que \u00a0su representado lo haya cometido y, (iv) que los occisos \u00a0no participaran en acciones delictivas. \u00a0\u00a0<\/p>\n<p>2. \u00a0Por \u00a0falso \u00a0juicio \u00a0de \u00a0existencia \u00a0por \u00a0omisi\u00f3n \u00a0en \u00a0el \u00a0fallo \u00a0de \u00a0segundo grado y, en el de primera, por suposici\u00f3n, \u00a0respecto \u00a0de la declaraci\u00f3n de Oscar Enrique Qui\u00f1onez Gamero, que condujo a la \u00a0falta \u00a0de \u00a0aplicaci\u00f3n \u00a0del \u00a0art\u00edculo \u00a0238 del C\u00f3digo de Procedimiento Penal e \u00a0indebida aplicaci\u00f3n del art\u00edculo 135 del C\u00f3digo Penal. \u00a0\u00a0<\/p>\n<p>Oscar Enrique Qui\u00f1onez, administrador de la \u00a0finca \u00a0Villa Lina, se\u00f1al\u00f3 que su empleador Rafael V\u00e1squez ten\u00eda que cancelar \u00a0anualmente \u00a0\u201cvacuna\u201d a la guerrilla, punto del cual dijo el a quo que (i) no \u00a0escuch\u00f3 \u00a0los \u00a0disparos \u00a0ni era objeto de extorsi\u00f3n, hurto o secuestro; (ii) el \u00a0grupo \u00a0de \u00a0militares \u00a0acamp\u00f3 \u00a08 d\u00edas antes en la finca; (iii) escuch\u00f3 que las \u00a0v\u00edctimas \u00a0no \u00a0eran \u00a0de la poblaci\u00f3n y, (iv) los militares s\u00ed se entrevistaron \u00a0con \u00a0su patr\u00f3n. A su turno, el ad quem rese\u00f1\u00f3 que el due\u00f1o de la finca neg\u00f3 \u00a0ser \u00a0objeto \u00a0de \u00a0extorsi\u00f3n \u00a0o \u00a0amenaza \u00a0de \u00a0secuestro. \u00a0Por consiguiente, no se \u00a0apreci\u00f3 \u00a0adecuadamente \u00a0la \u00a0probanza \u00a0junto \u00a0con \u00a0las dem\u00e1s, lo cual resultaba \u00a0determinante en la decisi\u00f3n adoptada. \u00a0\u00a0<\/p>\n<p>3. \u00a0Por \u00a0falso \u00a0juicio \u00a0de \u00a0existencia \u00a0por \u00a0omisi\u00f3n, \u00a0respecto de los testimonios de Rafael V\u00e1squez Soto, Adalberto Manuel \u00a0Marcelo \u00a0Ib\u00e1\u00f1ez \u00a0y \u00a0Hermes Mauricio Alvarado Sachica, que dio lugar a la falta \u00a0de \u00a0aplicaci\u00f3n \u00a0del \u00a0art\u00edculo 238 de la Ley 600 de 2000 e indebida aplicaci\u00f3n \u00a0del 135 de la Ley 599 de 2000. \u00a0\u00a0<\/p>\n<p>Rafael V\u00e1squez manifest\u00f3 que el d\u00eda de los \u00a0hechos \u00a0sali\u00f3 \u00a0a \u00a0embarcar un ganado y que la zona ha estado en conflicto entre \u00a0la \u00a0guerrilla \u00a0y \u00a0los \u00a0paramilitares \u00a0cuando \u00a0exist\u00edan. Adem\u00e1s, que no sabe de \u00a0secuestros \u00a0pues \u00a0a \u00a0lo \u00a0sumo la guerrilla pide vacuna a las personas que tienen \u00a0negocio \u00a0y \u00a0el \u00a0\u00fanico \u00a0problema \u00a0que tuvo fue con un muchacho que le rob\u00f3 unas \u00a0canecas \u00a0de \u00a0leche, \u00a0siendo \u00a0su situaci\u00f3n econ\u00f3mica acomodada; no obstante, la \u00a0primera \u00a0instancia \u00a0afirm\u00f3 \u00a0que el citado neg\u00f3 tajantemente que fuera v\u00edctima \u00a0de \u00a0extorsi\u00f3n y que adem\u00e1s no hab\u00eda realizado ning\u00fan negocio con ganado, sin \u00a0que \u00a0el \u00a0ad \u00a0quem \u00a0dijera \u00a0algo \u00a0sobre \u00a0el particular. Esta situaci\u00f3n permiti\u00f3 \u00a0asegurar \u00a0que \u00a0los \u00a0uniformados vinculados al proceso mintieron frente al motivo \u00a0de su desplazamiento al lugar del combate. \u00a0\u00a0<\/p>\n<p>A su vez, del testimonio de Adalberto Manuel \u00a0Marcelo \u00a0 Ib\u00e1\u00f1ez, \u00a0quien, \u00a0luego \u00a0de \u00a0referir \u00a0su \u00a0pertenencia \u00a0a \u00a0la \u00a0red \u00a0de \u00a0cooperantes \u00a0durante los a\u00f1os 2007 y 2008 y extraoficialmente tres a\u00f1os antes, \u00a0coment\u00f3 \u00a0sobre \u00a0el altercado de un muchacho con su patr\u00f3n de apellido V\u00e1squez \u00a0motivo \u00a0por \u00a0el \u00a0cual \u00a0le \u00a0iba \u00a0a \u00a0echar\u00a0 \u00a0la guerrilla, y del Mayor Hermes \u00a0Mauricio \u00a0Alvarado \u00a0Sachica, \u00a0Comandante \u00a0del Batall\u00f3n Contraguerrillas No. 10, \u00a0que \u00a0daba \u00a0cuenta de la orden de operaci\u00f3n emitida el 18 de junio, encaminada a \u00a0la \u00a0misi\u00f3n \u00a0t\u00e1ctica \u00a0Jerarca \u00a0y \u00a0de la cual se fragment\u00f3 la operaci\u00f3n del 20 \u00a0siguiente. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Tal \u00a0omisi\u00f3n \u00a0resulta \u00a0trascendente \u00a0porque \u00a0con tales probanzas se \u00a0demostraba \u00a0el \u00a0motivo de la operaci\u00f3n militar desplegada, que V\u00e1squez s\u00ed era \u00a0un \u00a0posible \u00a0objetivo \u00a0de la guerrilla, dado el pago de vacunas, y que ten\u00eda un \u00a0problema con un ex trabajador.\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a04. \u00a0Por \u00a0falso \u00a0juicio de identidad en la valoraci\u00f3n del testimonio \u00a0de \u00a0Wilson \u00a0Chica Monsalve, quien incurri\u00f3 en m\u00faltiples contradicciones en las \u00a0tres \u00a0declaraciones \u00a0que rindi\u00f3 en la actuaci\u00f3n en puntos tales como el motivo \u00a0de \u00a0la conversaci\u00f3n previa a los hechos sostenida con los presuntos autores del \u00a0il\u00edcito, \u00a0la \u00a0fecha \u00a0de la misma, el tiempo que gast\u00f3 su amigo H\u00e9ctor en ir y \u00a0volver, \u00a0o \u00a0que \u00a0el \u00a0militar perteneciera al Batall\u00f3n Rifles o contraguerrilla, \u00a0pues \u00a0no \u00a0concuerda con lo sostenido por Mayra Dol\u00ed Espinosa Rodr\u00edguez, Mar\u00eda \u00a0Piedad \u00a0Pulgar\u00edn \u00a0y \u00a0Ana \u00a0de \u00a0Jes\u00fas \u00a0Mart\u00ednez \u00a0respecto al lugar y raz\u00f3n del \u00a0desplazamiento \u00a0de \u00a0las \u00a0v\u00edctimas \u00a0fuera \u00a0de \u00a0su \u00a0residencia, \u00a0sin \u00a0que adem\u00e1s \u00a0ofreciera \u00a0elementos \u00a0que \u00a0permitan \u00a0identificar \u00a0al posible interlocutor.\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0Fiscal\u00eda \u00a0no \u00a0prob\u00f3 \u00a0que \u00a0lo \u00a0militares \u00a0vinculados fueran las \u00a0personas \u00a0que \u00a0refiri\u00f3 este testigo, obligaci\u00f3n que no pod\u00eda trasladarse a la \u00a0defensa, \u00a0surgiendo dudas acerca de que Chica Monsalve fuera testigo presencial, \u00a0toda \u00a0vez \u00a0que \u00a0sus \u00a0dichos \u00a0aparecen acomodados para indicar que hizo parte del \u00a0grupo \u00a0que \u00a0junto con los militares iban a hurtar dinero de la casa del ganadero \u00a0y \u00a0se \u00a0salv\u00f3 \u00a0del \u00a0fat\u00eddico \u00a0suceso; motivo por el cual improcedente resultaba \u00a0soportar en \u00e9l un fallo condenatorio. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a05. \u00a0Por \u00a0falso juicio de identidad en la apreciaci\u00f3n del testimonio \u00a0de \u00a0Elizabeth R\u00faa Morales y los informes de bal\u00edstica del 6 y 13 de septiembre \u00a0de \u00a02007, \u00a0en \u00a0lo atinente al estado de las prendas y las armas que portaban los \u00a0occisos \u00a0y \u00a0que \u00a0sirvi\u00f3 \u00a0para \u00a0descalificar \u00a0su \u00a0militancia \u00a0en \u00a0la \u00a0guerrilla. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0religiosa Elizabeth R\u00faa reconoci\u00f3 a uno de los fallecidos como \u00a0uno \u00a0de \u00a0los \u00a0guerrilleros \u00a0que \u00a0en \u00a0una \u00a0ocasi\u00f3n \u00a0visit\u00f3 \u00a0el \u00a0establecimiento \u00a0educativo \u00a0del \u00a0corregimiento \u00a0y los informes periciales daban cuenta de que las \u00a0armas \u00a0eran aptas para realizar disparos, de la compatibilidad de las municiones \u00a0encontradas \u00a0con las mismas, de modo que el hallazgo de aqu\u00e9llas en el sitio de \u00a0los \u00a0hechos \u00a0representaba \u00a0un peligro inminente para la vida de la tropa que los \u00a0enfrent\u00f3, asunto que no se consider\u00f3 en la actuaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Por \u00a0todo \u00a0lo \u00a0anterior solicit\u00f3 se case la sentencia y en su lugar \u00a0se \u00a0absuelva \u00a0a JUAN CARLOS SARMIENTO ROJAS por no existir prueba necesaria para \u00a0condenar y no desvirtuarse su presunci\u00f3n de inocencia. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES: \u00a0<\/p>\n<p>1. \u00a0La \u00a0demanda \u00a0ser\u00e1 inadmitida por cuanto \u00a0falta \u00a0a los presupuestos de t\u00e9cnica exigidos en esta sede, dado que los cargos \u00a0propuestos \u00a0contra \u00a0el \u00a0fallo de segunda instancia no son desarrollados conforme \u00a0con \u00a0los \u00a0requisitos previstos para cada uno de ellos, al omitir el casacionista \u00a0la \u00a0indicaci\u00f3n \u00a0clara y precisa de sus fundamentos, al tenor de lo dispuesto en \u00a0los numerales 3\u00ba y 4\u00ba del art\u00edculo 212 de la ley 600 de 2000. \u00a0\u00a0<\/p>\n<p>1.1. \u00a0 Los \u00a0reproches \u00a0postulados \u00a0por \u00a0el \u00a0demandante \u00a0no \u00a0consultan \u00a0con \u00a0los \u00a0principios \u00a0de \u00a0autonom\u00eda, \u00a0coherencia, no \u00a0contradicci\u00f3n \u00a0y rogaci\u00f3n que imponen la obligaci\u00f3n de presentarlos de manera \u00a0separada \u00a0y \u00a0subsidiaria, \u00a0cuando \u00a0con \u00a0su justificaci\u00f3n se excluyen entre s\u00ed, \u00a0conforme \u00a0con \u00a0las \u00a0pautas \u00a0reguladas \u00a0en el art\u00edculo 217 del estatuto procesal \u00a0aplicable. \u00a0\u00a0<\/p>\n<p>2. \u00a0 El \u00a0 primero \u00a0 carece \u00a0 de \u00a0 adecuada \u00a0fundamentaci\u00f3n \u00a0porque \u00a0si bien es cierto que se\u00f1ala los medios de convicci\u00f3n \u00a0sobre \u00a0los cuales recay\u00f3 el falso juicio de identidad que postula, esto es, las \u00a0declaraciones \u00a0de \u00a0Wilson de Jes\u00fas Chica Monsalve y Flor del Rosario Hern\u00e1ndez \u00a0y \u00a0trascribi\u00f3 \u00a0algunos \u00a0de sus apartes, no lo es menos que no identific\u00f3 c\u00f3mo \u00a0el \u00a0sentenciador \u00a0vari\u00f3 \u00a0su \u00a0contenido \u00a0material y expres\u00f3 cosa diferente a la \u00a0narrada por los deponentes. \u00a0\u00a0<\/p>\n<p>Recu\u00e9rdese \u00a0que este tipo de error requiere \u00a0que \u00a0el \u00a0demandante \u00a0no \u00a0s\u00f3lo \u00a0identifique \u00a0el \u00a0medio \u00a0de \u00a0prueba sobre el cual \u00a0recay\u00f3, \u00a0sino \u00a0que \u00a0acredite de manera objetiva que en el fallo se distorsion\u00f3 \u00a0su \u00a0contenido \u00a0material \u00a0para hacerle decir algo que en realidad no dice, porque \u00a0(i) \u00a0hace \u00a0una \u00a0lectura equivocada de sus palabras; (ii) lo adiciona o le mutila \u00a0apartes \u00a0relevantes, lo cual exige del demandante un ejercicio comparativo entre \u00a0lo \u00a0sostenido por el Tribunal y la probanza, a fin de evidenciar la distorsi\u00f3n, \u00a0sus \u00a0efectos \u00a0en \u00a0la \u00a0determinaci\u00f3n \u00a0adoptada \u00a0y \u00a0la forma de correcci\u00f3n de la \u00a0misma. \u00a0\u00a0<\/p>\n<p>El libelista no satisfizo tal carga, toda vez \u00a0que \u00a0\u00fanicamente critic\u00f3 a modo de alegato de instancia y con el fin de retomar \u00a0la \u00a0discusi\u00f3n \u00a0probatoria debidamente finiquitada en las instancias ordinarias, \u00a0las \u00a0conclusiones \u00a0del \u00a0fallador \u00a0seg\u00fan \u00a0las \u00a0cuales las personas fallecidas no \u00a0militaban \u00a0en \u00a0grupo \u00a0guerrillero, de acuerdo con lo narrado por los declarantes \u00a0sin evidenciar cu\u00e1l de sus manifestaciones fue falseada. \u00a0\u00a0<\/p>\n<p>3. \u00a0En \u00a0lo \u00a0atinente \u00a0al \u00a0segundo reparo, el \u00a0libelista \u00a0dej\u00f3 \u00a0de \u00a0lado \u00a0que \u00a0cuando \u00a0las \u00a0sentencias \u00a0de \u00a0primera \u00a0y segunda \u00a0instancias \u00a0guardan \u00a0conformidad conforman una unidad jur\u00eddica inescindible, de \u00a0modo \u00a0tal \u00a0que resulta contradictorio afirmar al mismo tiempo la presencia de un \u00a0error \u00a0de hecho por falso juicio de existencia por omisi\u00f3n y suposici\u00f3n, luego \u00a0incomprensible \u00a0se torna la queja relacionada con el testimonio de Oscar Enrique \u00a0Qui\u00f1onez, el que parece confunde con el de Rafael V\u00e1squez. \u00a0\u00a0<\/p>\n<p>4. \u00a0El \u00a0siguiente \u00a0ataque no coincide con la \u00a0realidad \u00a0procesal, \u00a0pues \u00a0no \u00a0es \u00a0cierto \u00a0que \u00a0los falladores no apreciaran los \u00a0testimonios \u00a0de Rafael V\u00e1squez Soto, Adalberto Manuel Marcelo Ib\u00e1\u00f1ez y Hermes \u00a0Mauricio \u00a0Alvarado \u00a0S\u00e1chica, \u00a0como se observa a folios 4, 20, 21 y 22 del fallo \u00a0de \u00a0primer \u00a0grado \u00a0y\u00a0 \u00a014, \u00a018, 34, 37\u00a0 de la de segundo y si bien, en \u00a0cuanto \u00a0al \u00a0\u00faltimo, \u00a0no \u00a0se \u00a0aprecia \u00a0una \u00a0argumentaci\u00f3n \u00a0tendiente a restar o \u00a0conferirle \u00a0merito \u00a0suasorio, \u00a0tampoco ello conlleva la prosperidad del cargo al \u00a0no \u00a0acreditarse \u00a0su \u00a0trascendencia, en tanto nunca pusieron en duda la presencia \u00a0en \u00a0la \u00a0zona de la compa\u00f1\u00eda al mando del procesado teniente SARMIENTO ROJAS en \u00a0ejecuci\u00f3n de operaciones militares. \u00a0\u00a0<\/p>\n<p>En \u00a0tal virtud, los argumentos que expone el \u00a0demandante \u00a0se \u00a0muestran \u00a0como \u00a0la \u00a0prolongaci\u00f3n \u00a0del \u00a0debate \u00a0postulado por la \u00a0defensa, \u00a0que no tuvo eco en las autoridades judiciales, quienes encontraron con \u00a0fundamento \u00a0en \u00a0\u00e9stos \u00a0y \u00a0otros elementos de convicci\u00f3n acreditada en grado de \u00a0certeza la conducta punible y la responsabilidad del sentenciado. \u00a0\u00a0<\/p>\n<p>5. \u00a0En \u00a0el \u00a0cuarto \u00a0cargo, consistente en un \u00a0falso \u00a0 juicio \u00a0 de \u00a0identidad \u00a0frente \u00a0a \u00a0la \u00a0testificaci\u00f3n \u00a0de \u00a0Wilson \u00a0Chica \u00a0Monsalve,\u00a0 \u00a0al \u00a0igual que en el primero, la defensa no mostr\u00f3 la mutaci\u00f3n \u00a0de \u00a0su \u00a0exposici\u00f3n, \u00a0lo que intent\u00f3 fue cuestionar la credibilidad de su dicho \u00a0al \u00a0advertir contradicciones entre las diferentes versiones que rindi\u00f3 ante las \u00a0autoridades \u00a0jurisdiccionales y frente a lo manifestado por\u00a0 las familiares \u00a0de \u00a0los \u00a0fallecidos, \u00a0quienes \u00a0ten\u00edan \u00a0un \u00a0conocimiento diferente del destino y \u00a0actividades \u00a0 a \u00a0 desempe\u00f1ar \u00a0 por \u00a0 aqu\u00e9llos, \u00a0asunto \u00a0que \u00a0dista \u00a0del \u00a0yerro \u00a0enrostrado. \u00a0\u00a0<\/p>\n<p>Si la inconformidad expresada por la defensa \u00a0reca\u00eda \u00a0sobre \u00a0la \u00a0eficacia \u00a0que \u00a0los jueces confirieron o negaron a los medios \u00a0probatorios, \u00a0eventualmente \u00a0s\u00f3lo \u00a0pod\u00eda ser cuestionada por v\u00eda del error de \u00a0hecho \u00a0por \u00a0falso raciocinio, debi\u00e9ndose cumplir con la carga, no satisfecha en \u00a0este \u00a0caso, \u00a0de \u00a0enunciar \u00a0c\u00f3mo \u00a0las \u00a0sentencias \u00a0desconocieron \u00a0alguno \u00a0de los \u00a0postulados \u00a0de la sana critica: si una ley de la ciencia, un principio l\u00f3gico o \u00a0una m\u00e1xima de la experiencia. \u00a0\u00a0<\/p>\n<p>6. El anterior argumento se hace extensivo al \u00a0\u00faltimo \u00a0de \u00a0los \u00a0reproches \u00a0que \u00a0corresponde \u00a0con las probanzas, testimonial de \u00a0Elizabeth \u00a0R\u00faa \u00a0Morales y periciales de bal\u00edstica, del 6 y 13 de septiembre de \u00a02007. \u00a0 \u00a0Frente \u00a0 \u00a0a \u00a0 la \u00a0 primera, \u00a0 el \u00a0 a \u00a0 quo1 \u00a0 no \u00a0 mutil\u00f3, \u00a0 supuso \u00a0 o \u00a0tergivers\u00f3 \u00a0lo \u00a0advertido \u00a0por \u00a0la \u00a0religiosa \u00a0en \u00a0lo \u00a0atinente \u00a0a \u00a0la supuesta \u00a0pertenencia \u00a0de \u00a0uno de los occisos a la guerrilla, por el contrario, consider\u00f3 \u00a0su \u00a0dicho en ese tema, s\u00f3lo que no lo encontr\u00f3 suficiente para descalificar la \u00a0existencia \u00a0del \u00a0delito, \u00a0por \u00a0cuanto, \u00a0a\u00fan \u00a0si \u00a0fuera \u00a0as\u00ed, no se contaba con \u00a0evidencia \u00a0del \u00a0ataque a las fuerzas militares o actos de hostilidad de parte de \u00a0los \u00a0occisos \u00a0y s\u00ed respecto que la aprehensi\u00f3n de las v\u00edctimas sucedi\u00f3 sobre \u00a0las \u00a0 6:30 \u00a0 de \u00a0la \u00a0tarde \u00a0y \u00a0los \u00a0disparos \u00a0que \u00a0segaron \u00a0su \u00a0vida \u00a0se \u00a0dieron \u00a0aproximadamente \u00a0a \u00a0las 9 de la noche, cuando ya se encontraban bajo la custodia \u00a0del \u00a0Estado \u00a0y \u00a0hab\u00edan, \u00a0en \u00a0gracia \u00a0de \u00a0discusi\u00f3n, adquirido la calidad de no \u00a0combatientes \u00a0y, \u00a0por \u00a0consiguiente, \u00a0de \u00a0personas \u00a0protegidas \u00a0por \u00a0el \u00a0derecho \u00a0internacional humanitario. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Respecto \u00a0de \u00a0los \u00a0informes \u00a0de bal\u00edstica y la aptitud de las armas \u00a0incautadas \u00a0para \u00a0disparar, \u00a0se \u00a0observa que ello tampoco fue desmentido por los \u00a0juzgadores, \u00a0singular \u00a0o colegiado, tan s\u00f3lo se sirvieron de otros elementos de \u00a0prueba \u00a0como \u00a0las fotograf\u00edas acopiadas para concluir el poco uso, o no diario, \u00a0de las mismas ante su deterioro f\u00edsico. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a07. \u00a0Luego, en la demanda se observa es el inter\u00e9s del representante \u00a0judicial \u00a0de \u00a0JUAN \u00a0CARLOS SARMIENTO ROJAS en continuar con el debate probatorio \u00a0ya \u00a0culminado, \u00a0en \u00a0contrav\u00eda \u00a0de \u00a0la \u00a0naturaleza extraordinaria del recurso de \u00a0casaci\u00f3n, \u00a0el \u00a0cual \u00a0requiere \u00a0de la demostraci\u00f3n de yerros atacables conforme \u00a0con \u00a0las \u00a0causales \u00a0descritas \u00a0en \u00a0el \u00a0art\u00edculo \u00a0207 \u00a0de la Ley 600 de 2000 que \u00a0permitan \u00a0derruir la doble presunci\u00f3n de acierto y legalidad que le asiste a la \u00a0decisi\u00f3n impugnada. \u00a0\u00a0<\/p>\n<p>8. \u00a0Por \u00a0lo \u00a0anterior, \u00a0la \u00a0Sala \u00a0habr\u00e1 \u00a0de \u00a0inadmitir \u00a0la \u00a0demanda \u00a0que \u00a0se \u00a0examina, \u00a0m\u00e1s aun cuando no se advierte que el \u00a0recurso \u00a0est\u00e9 \u00a0convocado \u00a0a \u00a0cumplir \u00a0alguna \u00a0de \u00a0sus finalidades o que se haya \u00a0vulnerado \u00a0 garant\u00edas \u00a0 de \u00a0 orden \u00a0fundamental \u00a0que \u00a0impongan \u00a0su \u00a0protecci\u00f3n \u00a0oficiosa. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la Corte Suprema \u00a0de Justicia, Sala de Casaci\u00f3n Penal, \u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>No admitir la demanda de casaci\u00f3n presentada \u00a0por la defensa de JUAN CARLOS SARMIENTO ROJAS. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta \u00a0decisi\u00f3n \u00a0no \u00a0procede \u00a0recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese, \u00a0c\u00famplase \u00a0y \u00a0devu\u00e9lvase \u00a0al \u00a0Tribunal de origen, \u00a0\u00a0<\/p>\n<p>JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0<\/p>\n<p>FERNANDO ALBERTO CASTRO CABALLERO \u00a0<\/p>\n<p>EUGENIO FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>GUSTAVO ENRIQUE MALO FERN\u00c1NDEZ \u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>PATRICIA SALAZAR CUELLAR \u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>Nubia Yolanda Nova Garc\u00eda \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 Donde \u00a0se aprecia una valoraci\u00f3n concreta frente al medio suasorio \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 LUIS GUILLERMO SALAZAR OTERO \u00a0 Magistrado Ponente \u00a0 AP4404-2015 \u00a0 Rad. 45999 \u00a0 Aprobado Acta No. 271 \u00a0 Bogot\u00e1, \u00a0D.C.,\u00a0 \u00a0cinco (5) de agosto de \u00a0dos mil quince (2015). \u00a0\u00a0 ASUNTO: \u00a0 La \u00a0Corte decide si admite o no la demanda de \u00a0casaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-31199","post","type-post","status-publish","format-standard","hentry","category-23"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/31199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=31199"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/31199\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=31199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=31199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=31199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}