{"id":3111,"date":"2023-09-08T14:29:49","date_gmt":"2023-09-08T14:29:49","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/15189mar1\/"},"modified":"2023-09-08T14:29:49","modified_gmt":"2023-09-08T14:29:49","slug":"15189mar1","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/15189mar1\/","title":{"rendered":"15189mar1"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso N\u00b0 15189 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>Dr. JORGE AN\u00cdBAL G\u00d3MEZ GALLEGO \u00a0<\/p>\n<p>Aprobado Acta No. 38 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Santaf\u00e9 de Bogot\u00e1, D.C, catorce de marzo de dos mil. \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0De \u00a0acuerdo \u00a0con \u00a0lo \u00a0previsto \u00a0en \u00a0el \u00a0art\u00edculo 235 del C\u00f3digo de \u00a0Procedimiento \u00a0Penal, \u00a0examina la Corte la viabilidad de la demanda de revisi\u00f3n \u00a0presentada \u00a0por \u00a0el \u00a0defensor \u00a0del \u00a0condenado \u00a0WILSON \u00a0MONROY GAIT\u00c1N, contra la \u00a0sentencia \u00a0de \u00a0segunda instancia proferida por el Tribunal Superior del Distrito \u00a0Judicial \u00a0de \u00a0Neiva el 9 de diciembre de 1996, confirmatoria de la que en primer \u00a0grado \u00a0hab\u00eda \u00a0emitido \u00a0el Juzgado 2 Penal del Circuito de la misma ciudad el 17 \u00a0de \u00a0octubre \u00a0de id\u00e9ntica anualidad y mediante la cual se le declar\u00f3 penalmente \u00a0responsable \u00a0de \u00a0los \u00a0injustos \u00a0de \u00a0homicidio, \u00a0en la persona de Di\u00f3genes Tovar \u00a0Ram\u00edrez, \u00a0y \u00a0porte ilegal de arma de fuego de defensa personal, imponi\u00e9ndosele \u00a0la \u00a0pena \u00a0principal \u00a0de \u00a025 \u00a0a\u00f1os \u00a0y \u00a06 \u00a0meses \u00a0de \u00a0prisi\u00f3n, \u00a0la \u00a0accesoria de \u00a0interdicci\u00f3n \u00a0de \u00a0derechos \u00a0y \u00a0funciones p\u00fablicas por el t\u00e9rmino de 10 a\u00f1os, \u00a0m\u00e1s \u00a0la \u00a0obligaci\u00f3n \u00a0de \u00a0resarcir \u00a0los perjuicios materiales y morales en suma \u00a0equivalente a 800 gramos oro. \u00a0\u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Al \u00a0desatar \u00a0la \u00a0apelaci\u00f3n \u00a0de \u00a0la \u00a0sentencia \u00a0de \u00a0primer \u00a0grado el \u00a0Tribunal los narr\u00f3 de la siguiente manera: \u00a0\u00a0<\/p>\n<p>\u201cOcurrieron la noche del 8 de abril de 1995 \u00a0en \u00a0el \u00a0Parque \u00a0de la Inspecci\u00f3n de Polic\u00eda El Toro, comprensi\u00f3n municipal de \u00a0Alcegiras, \u00a0Huila, \u00a0cuando \u00a0al \u00a0encontrarse \u00a0en \u00a0una \u00a0venta de empanadas, Wilson \u00a0Monroy \u00a0Gait\u00e1n \u00a0y \u00a0Di\u00f3genes Tovar Ram\u00edrez, tuvieron un altercado que culmin\u00f3 \u00a0con \u00a0la \u00a0muerte \u00a0de \u00a0\u00e9ste \u00a0\u00faltimo \u00a0a \u00a0causa \u00a0de \u00a0dos tiros de rev\u00f3lver que le \u00a0propin\u00f3 el primero\u201d. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Con \u00a0base \u00a0en \u00a0la causal tercera del art\u00edculo 232 del c\u00f3digo penal \u00a0adjetivo, \u00a0el \u00a0accionante \u00a0exora la revisi\u00f3n del fallo cuestionado afirmando la \u00a0existencia \u00a0de un hecho nuevo, desconocido por los juzgadores pues jam\u00e1s lleg\u00f3 \u00a0al \u00a0proceso, \u00a0con \u00a0pruebas \u00a0que \u00a0en \u00a0conjunto \u00a0tienen \u00a0el \u00a0valor suficiente para \u00a0modificar \u00a0 \u00a0la \u00a0 \u00a0responsabilidad \u00a0 \u00a0penal \u00a0 \u00a0que \u00a0 \u00a0le \u00a0 fuera \u00a0 deducida \u00a0 al \u00a0sentenciado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Al \u00a0 efecto \u00a0 sostiene \u00a0 que \u00a0 la \u00a0 investigaci\u00f3n \u00a0 no \u00a0apunt\u00f3 \u00a0al \u00a0esclarecimiento \u00a0del \u00a0itinerario \u00a0del \u00a0occiso \u00a0momentos \u00a0antes de producirse los \u00a0impactos \u00a0que \u00a0segaron \u00a0la vida de la v\u00edctima, como tampoco de las personas que \u00a0depart\u00edan \u00a0con \u00e9sta, sino que se centr\u00f3 en los pormenores del resultado final \u00a0y \u00a0a \u00a0un \u00a0interrogatorio \u00a0superficial \u00a0de \u00a0algunos de sus acompa\u00f1antes que nada \u00a0aportaron al conocimiento de la verdad. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0seguida \u00a0hace un relato seg\u00fan el cual junto a la mesa en que se \u00a0encontraba \u00a0el \u00a0occiso \u00a0dentro \u00a0de la cantina de la se\u00f1ora Ana Rita de Trujillo \u00a0acompa\u00f1ado \u00a0de los se\u00f1ores Rigoberto Tovar, Jos\u00e9 Lizardo Tovar, Eliecer Pinto \u00a0y \u00a0 \u00a0Elver \u00a0 \u00a0N \u00a0 \u00a0\u201cEl \u00a0 \u00a0Calbo\u201d, \u00a0 asegura, tambi\u00e9n \u00a0se \u00a0hallaban \u00a0Orlando Arias, Jorge Mauricio Lozano y Edgar Salazar, personas que \u00a0nunca \u00a0fueron \u00a0llamadas \u00a0a declarar y quienes\u00a0 escucharon a Di\u00f3genes decir \u00a0que \u00a0matar\u00eda \u00a0a \u00a0Wilson \u00a0cuando \u00a0\u00e9ste \u00a0pas\u00f3 \u00a0por cercan\u00edas del lugar junto a \u00a0Orlando \u00a0Gait\u00e1n \u00a0Yanguma, tom\u00f3 su arma y al observar que tan s\u00f3lo contaba con \u00a0una \u00a0o dos balas le solicit\u00f3 munici\u00f3n a Elver, sali\u00f3 del establecimiento ante \u00a0la \u00a0mirada \u00a0de \u00a0los \u00a0testigos \u00a0y \u00a0cuando \u00a0todo \u00a0hac\u00eda \u00a0pensar que cumplir\u00eda su \u00a0prop\u00f3sito \u00a0al \u00a0llegar \u00a0al puesto de empanadas de la se\u00f1ora Nohem\u00ed, escucharon \u00a0los \u00a0disparos \u00a0que \u00a0para \u00a0sorpresa \u00a0de todos dieron como resultado la muerte del \u00a0se\u00f1or Tovar. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Hecho \u00a0nuevo que, asevera el demandante, por petici\u00f3n suya dieron a \u00a0conocer \u00a0los \u00a0testigos ante la Notar\u00eda Quinta del Circuito de Neiva, dejando al \u00a0descubierto \u00a0la \u00a0conducta \u00a0premeditada y determinada del occiso al momento de ir \u00a0en \u00a0b\u00fasqueda \u00a0de Monroy, quien desconoc\u00eda el designio criminal del perseguidor \u00a0\u201cy suscit\u00f3 el dudoso desaf\u00edo que dieron como hecho \u00a0cierto \u00a0 \u00a0 los \u00a0 \u00a0 investigadores \u00a0 \u00a0y \u00a0 \u00a0falladores \u00a0 \u00a0en \u00a0 \u00a0sus \u00a0 \u00a0respectivas \u00a0decisiones\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Al \u00a0 \u00a0 \u00a0pasar \u00a0 \u00a0 \u00a0al \u00a0 \u00a0 \u00a0t\u00edtulo \u00a0 \u00a0 \u00a0denominado \u00a0 \u00a0 \u00a0\u201cFUNDAMENTOS \u00a0DE \u00a0HECHO \u00a0Y DE DERECHO\u201d, \u00a0el \u00a0accionante \u00a0resalta la importancia que en toda investigaci\u00f3n penal tiene la \u00a0observaci\u00f3n \u00a0integral\u00a0 \u00a0e \u00a0imparcial de los hechos, tarea con que se logra \u00a0el \u00a0esclarecimiento \u00a0de \u00a0la \u00a0verdad \u00a0real y no de la parcial como ocurri\u00f3 en el \u00a0caso, \u00a0en \u00a0el que, reitera, lo que constituye el nuevo hecho no s\u00f3lo refulge de \u00a0la \u00a0prueba \u00a0nueva \u00a0aportada \u00a0sino \u00a0tambi\u00e9n \u00a0de \u00a0la \u00a0apreciaci\u00f3n \u00a0que del mismo \u00a0hicieron \u00a0los \u00a0acompa\u00f1antes \u00a0del \u00a0occiso, \u00a0esta \u00a0la raz\u00f3n para que el indagado \u00a0hubiera \u00a0manifestado \u00a0que \u00a0una vez herida mortalmente la v\u00edctima fue perseguido \u00a0por \u00a0el \u00a0hermano \u00a0de \u00a0\u00e9sta, \u00a0en tanto que la se\u00f1ora Mar\u00eda Nohem\u00ed -due\u00f1a del \u00a0expendio \u00a0de empanadas- afirm\u00f3 que se o\u00edan disparos por el lado del puente, es \u00a0decir, \u00a0el \u00a0consangu\u00edneo \u00a0no \u00a0fue \u00a0ajeno \u00a0al prop\u00f3sito del occiso de ultimar a \u00a0Monroy. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Esta \u00a0situaci\u00f3n \u00a0hace \u00a0f\u00e1cil \u00a0comprender \u00a0el \u00a0proceder \u00a0r\u00e1pido de \u00a0Di\u00f3genes \u00a0al \u00a0llegar \u00a0a la venta de empanadas, hecho uniformemente depuesto por \u00a0los \u00a0testigos \u00a0Enith \u00a0Mar\u00edn \u00a0S\u00e1nchez, Leidy Patricia Perdomo y Orlando Gait\u00e1n \u00a0Yanguma, \u00a0de ah\u00ed que con buen criterio no se pueda establecer de acuerdo con la \u00a0versi\u00f3n \u00a0de \u00a0las \u00a0damas \u00a0qui\u00e9n \u00a0fue \u00a0el \u00a0incitador \u00a0o \u00a0provocador \u201cde \u00a0un \u00a0preconizado \u00a0desaf\u00edo \u00a0que nunca existi\u00f3\u201d ya \u00a0 que \u00a0 el \u00a0designio \u00a0criminal \u00a0de \u00a0quien \u00a0resultara \u00a0luego\u00a0 \u00a0v\u00edctima, \u00a0hab\u00eda \u00a0sido \u00a0tomado \u00a0y \u00a0decidido \u00a0antes \u00a0de llegar al sitio donde se \u00a0finiquit\u00f3 \u00a0el \u00a0suceso; \u00a0planteamiento \u00a0que \u00a0conlleva al demandante a considerar \u00a0cre\u00edble \u00a0 lo \u00a0 que \u00a0 dijo \u00a0 escuchar \u00a0la \u00a0testigo \u00a0Leidy, \u00a0concordante \u00a0con \u00a0el \u00a0desenvolvimiento \u00a0buscado \u00a0por \u00a0Di\u00f3genes, \u00a0no \u00a0as\u00ed \u00a0con \u00a0lo \u00a0sostenido \u00a0por la \u00a0nerviosa \u00a0e inducida Enith quien en su ampliaci\u00f3n asever\u00f3 no recordar la frase \u00a0\u201cque \u00a0 si \u00a0 se \u00a0 iban \u00a0 a \u00a0 matar\u201d, \u00a0alocuci\u00f3n \u00a0que \u00a0se \u00a0aduce \u00a0pronunciada \u00a0por \u00a0el \u00a0procesado \u00a0con \u00a0la \u00a0inmediata \u00a0 producci\u00f3n \u00a0 de \u00a0 los \u00a0 disparos \u00a0 que \u00a0 privaron \u00a0 de \u00a0la \u00a0vida \u00a0a \u00a0Tovar. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0De \u00a0esta \u00a0forma \u00a0consolida \u00a0en \u00a0el nuevo hecho la explicaci\u00f3n de la \u00a0posici\u00f3n \u00a0vacilante \u00a0y mentirosa de los testigos Jos\u00e9 Lizardo Tovar y Eli\u00e9cer \u00a0Pinto, \u00a0de \u00a0quienes asegura trataron de acomodar al occiso montado en un caballo \u00a0y \u00a0a \u00a0toda \u00a0costa \u00a0negar que en el momento final del suceso se encontraban en la \u00a0cantina \u00a0y \u00a0que \u00a0el \u00a0difunto \u00a0portaba un arma, maniobra no obstante insuficiente \u00a0para \u00a0ocultar \u00a0que los mentados estuvieron en el sitio, constituy\u00e9ndose as\u00ed el \u00a0indicio \u00a0que \u00a0permite \u00a0descubrir \u00a0la agresi\u00f3n inminente que se cerni\u00f3 sobre el \u00a0procesado, \u00a0de parte de una persona peligrosa, pendenciera y belicosa que ten\u00eda \u00a0antecedentes \u00a0en \u00a0contra \u00a0de \u00a0la \u00a0familia \u00a0de \u00a0aqu\u00e9l,\u00a0 seg\u00fan da cuenta la \u00a0versi\u00f3n \u00a0 de \u00a0Alfonso \u00a0Gait\u00e1n \u00a0y \u00a0el \u00a0denuncio \u00a0formulado \u00a0por \u00a0Wilmer \u00a0Monroy \u00a0Gait\u00e1n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Por \u00a0 todo \u00a0 lo \u00a0 anterior \u00a0 aduce \u00a0que \u00a0el \u00a0procesado \u00a0\u201cten\u00eda \u00a0en \u00a0peligro \u00a0su \u00a0vida \u00a0inclusive \u00a0antes \u00a0de \u00a0intercambiar \u00a0cualquier \u00a0palabra con el hoy occiso que sali\u00f3 de la cantina ANA RITA TRUJILLO, \u00a0a \u00a0matarlo, \u00a0en fin, con ese prop\u00f3sito se dirigi\u00f3 hasta \u00e9l, siendo entendible \u00a0la \u00a0inminencia de la agresi\u00f3n, porque la decisi\u00f3n de matar ya la hab\u00eda tomado \u00a0desde \u00a0cuando \u00a0carg\u00f3 \u00a0el \u00a0arma con ese prop\u00f3sito, otro fen\u00f3meno es que WILSON \u00a0MONROY, \u00a0no \u00a0es \u00a0el \u00a0que \u00a0primero \u00a0dispara, \u00a0sino el que responde, luego no cabe \u00a0predicar \u00a0que \u00a0\u00e9l \u00a0previ\u00f3 el ataque inminente que desencadenaba DIOGENES (sic) \u00a0en \u00a0su \u00a0contra, \u00a0algo \u00a0que \u00a0era \u00a0inesperado, \u00a0sin embargo, logr\u00f3 responder a la \u00a0agresi\u00f3n \u00a0debido \u00a0al \u00a0miedo \u00a0que \u00a0encarnaba DIOGENES (sic), para su familia y a \u00a0tener \u00a0 en \u00a0 su \u00a0 poder \u00a0 un \u00a0arma \u00a0id\u00f3nea \u00a0y \u00a0adecuada \u00a0para \u00a0responder \u00a0a \u00a0la \u00a0agresi\u00f3n\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Finaliza \u00a0afirmando \u00a0que entonces el proceder del procesado entra\u00f1a \u00a0una \u00a0leg\u00edtima \u00a0defensa \u00a0pues \u201cla agresi\u00f3n o peligro \u00a0si \u00a0fueron actuales e inminentes y mediaron al momento de la reacci\u00f3n defensiva \u00a0de WILSON\u201d. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0acci\u00f3n \u00a0de \u00a0revisi\u00f3n, mecanismo excepcional a trav\u00e9s del cual \u00a0la \u00a0ley \u00a0brinda \u00a0al \u00a0ciudadano \u00a0la \u00a0oportunidad \u00a0para \u00a0que \u00a0se restaure el valor \u00a0axiol\u00f3gico \u00a0de \u00a0la \u00a0justicia quebrantado mediante un fallo ejecutoriado, supone \u00a0de \u00a0parte \u00a0del \u00a0demandante \u00a0la \u00a0irrefutable \u00a0comprobaci\u00f3n \u00a0de cualquiera de las \u00a0causales \u00a0 previstas \u00a0 en \u00a0 el \u00a0 art\u00edculo \u00a0232 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Trat\u00e1ndose \u00a0de \u00a0la \u00a0causal \u00a0tercera, que es la que en esta ocasi\u00f3n \u00a0propone \u00a0el \u00a0actor como fundamento de su libelo,\u00a0 la Corte ha ense\u00f1ado que \u00a0la \u00a0prueba \u00a0nueva \u00a0es \u00a0aquella que surge despu\u00e9s de la emisi\u00f3n de la sentencia \u00a0condenatoria \u00a0y \u00a0por \u00a0cuyo \u00a0desconocimiento \u00a0en \u00a0las \u00a0instancias \u00a0procesales \u00a0el \u00a0funcionario \u00a0no \u00a0pudo \u00a0valorarla, \u00a0dejando \u00a0por \u00a0ello de apreciar hechos con los \u00a0cuales \u00a0no \u00a0le \u00a0hubiera \u00a0sido posible como autoridad judicial el establecimiento \u00a0del \u00a0juicio \u00a0positivo \u00a0de \u00a0responsabilidad \u00a0penal \u00a0de \u00a0la \u00a0condena \u00a0impartida al \u00a0procesado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0De \u00a0 \u00a0esta \u00a0 \u00a0forma \u00a0 \u00a0la \u00a0 \u00a0aparici\u00f3n \u00a0 de \u00a0 hechos \u00a0 \u201cnuevos\u201d \u00a0o \u00a0de \u00a0pruebas con id\u00e9ntico \u00a0car\u00e1cter, \u00a0constituye \u00a0el \u00a0eje \u00a0central \u00a0desde \u00a0el \u00a0cual \u00a0debe \u00a0proyectarse \u00a0la \u00a0petici\u00f3n \u00a0de \u00a0revisi\u00f3n, \u00a0raz\u00f3n \u00a0por \u00a0la cual en ning\u00fan caso la acci\u00f3n puede \u00a0convertirse \u00a0en \u00a0escenario \u00a0de \u00a0debate \u00a0sobre \u00a0puntos \u00a0ya \u00a0resueltos durante las \u00a0instancias \u00a0so \u00a0pretexto \u00a0de la existencia de elementos por cuyo desconocimiento \u00a0se produjo el fallo adverso a los intereses del procesado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Es \u00a0el \u00a0caso \u00a0frente \u00a0al cual se encuentra la Sala, am\u00e9n de que con \u00a0las \u00a0declaraciones que dice el accionante no fueron arrimadas al tr\u00e1mite cuando \u00a0era \u00a0de \u00a0vital \u00a0importancia \u00a0adjuntarlas \u00a0porque con ellas se demuestra el hecho \u00a0nuevo \u00a0de \u00a0la \u00a0voluntad criminal que ten\u00eda el occiso antes de ser fulminado por \u00a0el \u00a0hoy \u00a0condenado, \u00a0no \u00a0hay \u00a0asomo \u00a0de \u00a0que por ello el fallo hubiese resultado \u00a0condenatorio en claro desconocimiento de una leg\u00edtima defensa. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0A \u00a0esta \u00a0conclusi\u00f3n \u00a0se \u00a0llega \u00a0si \u00a0se \u00a0atiende \u00a0al contenido de la \u00a0sentencia, \u00a0pues en \u00e9sta qued\u00f3 descartada la unidad de acto requerida entre la \u00a0supuesta \u00a0agresi\u00f3n \u00a0y \u00a0la defensa con que el libelista pretende sacar avante su \u00a0pretensi\u00f3n \u00a0con \u00a0el \u00a0argumento \u00a0de \u00a0que el occiso fue visto y escuchado por los \u00a0testigos \u00a0Orlando \u00a0Arias, \u00a0Jorge \u00a0Mauricio Lozano y Edgar Salazar, cuando al ver \u00a0pasar \u00a0al \u00a0procesado \u00a0Wilson\u00a0 \u00a0manifest\u00f3 que lo iba a matar y al efecto se \u00a0vali\u00f3 \u00a0de \u00a0uno \u00a0de sus acompa\u00f1antes para cargar el arma dirigi\u00e9ndose hacia la \u00a0supuesta v\u00edctima para materializar el designio criminal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a0Tribunal \u00a0despu\u00e9s \u00a0de \u00a0valorar las pruebas determin\u00f3 que en el \u00a0lugar \u00a0de \u00a0los \u00a0hechos \u00a0\u2013el \u00a0expendio \u00a0de \u00a0empanadas- \u00a0y \u00a0en \u00a0el momento en que se produjeron los disparos se \u00a0encontraban \u00a0Enith \u00a0Mar\u00edn, \u00a0Leidy \u00a0Patricia \u00a0Perdomo y Orlando Gait\u00e1n Yanguma, \u00a0quienes \u00a0si \u00a0bien no fueron uniformes en declarar cu\u00e1l de los protagonistas fue \u00a0el \u00a0que \u00a0provoc\u00f3 \u00a0al \u00a0otro, \u00a0tal \u00a0hecho \u00a0pudo \u00a0aclararlo \u00a0con \u00a0la \u00a0injurada del \u00a0procesado, \u00a0el \u00a0cual \u00a0reconoci\u00f3 \u00a0haber \u00a0iniciado el intercambio de palabras que \u00a0molest\u00f3 \u00a0a \u00a0la \u00a0v\u00edctima \u00a0y \u00a0concluy\u00f3 \u00a0con \u00a0el \u00a0reto \u00a0al \u00a0que il\u00edcitamente se \u00a0sometieron los rijosos. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Se lee en la sentencia: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u201cDel \u00a0an\u00e1lisis \u00a0conjunto de los testimonios referidos se advierte \u00a0que \u00a0previo \u00a0al \u00a0desenlace tr\u00e1gico hubo un intercambio de palabras, que parti\u00f3 \u00a0precisamente \u00a0de \u00a0Monroy \u00a0Gait\u00e1n, \u00a0reclamo \u00a0que fue la ignici\u00f3n para rememorar \u00a0desavenencias \u00a0familiares \u00a0suscitadas \u00a0meses \u00a0atr\u00e1s, \u00a0y de esa manera surgir el \u00a0reto \u00a0a \u00a0que aluden al un\u00edsono Enith Mar\u00edn, Leidy Perdomo y Orlando Gait\u00e1n, y \u00a0que \u00a0resulta \u00a0reafirmado \u00a0por el inculpado, destac\u00e1ndose enseguida el encuentro \u00a0f\u00edsico, \u00a0donde \u00a0se \u00a0sostiene \u00a0por los deponentes mencionados -excepto Enith -se \u00a0esgrimieron \u00a0armas \u00a0de \u00a0fuego \u00a0de \u00a0parte \u00a0y parte, culminando en forma r\u00e1pida a \u00a0consecuencia de los medios utilizados por los contendientes\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Este \u00a0an\u00e1lisis \u00a0permiti\u00f3 \u00a0al \u00a0Tribunal \u00a0deducir la responsabilidad \u00a0penal \u00a0del \u00a0procesado, \u00a0la \u00a0misma \u00a0que ahora resulta imposible desconocer con el \u00a0argumento \u00a0de \u00a0que \u00a0aparecieron \u00a0pruebas \u00a0que \u00a0destacan \u00a0el \u00a0hecho \u00a0nuevo \u00a0de la \u00a0anticipada \u00a0voluntad \u00a0que \u00a0ten\u00eda \u00a0Tovar de matar a Wilson, pues en la sentencia \u00a0con \u00a0que \u00a0el \u00a0asunto \u00a0se \u00a0convirti\u00f3 \u00a0en \u00a0res iudicata, \u00a0paladinamente \u00a0 se \u00a0descart\u00f3 \u00a0la \u00a0aducida \u00a0leg\u00edtima \u00a0defensa \u00a0en \u00a0el actuar del inculpado, habida cuenta que el homicidio no fue cosa \u00a0distinta \u00a0al \u00a0resultado \u00a0de \u00a0la \u00a0ri\u00f1a que propici\u00f3 el ahora accionante, raz\u00f3n \u00a0m\u00e1s \u00a0que \u00a0suficiente \u00a0para \u00a0que \u00a0los \u00a0testimonios \u00a0que \u00a0acompa\u00f1\u00f3 a la demanda \u00a0resulten \u00a0absolutamente \u00a0est\u00e9riles \u00a0para \u00a0promover \u00a0siquiera la revisi\u00f3n de un \u00a0fallo \u00a0que \u00a0por \u00a0su \u00a0ejecutoria \u00a0est\u00e1 \u00a0ungida \u00a0de \u00a0los \u00a0atributos \u00a0de acierto y \u00a0legalidad. \u00a0\u00a0<\/p>\n<p>Y \u00a0un \u00a0tal \u00a0empe\u00f1o \u00a0se \u00a0hace \u00a0todav\u00eda m\u00e1s \u00a0improcedente \u00a0si \u00a0se para mientes en que en un sistema como el nuestro, donde la \u00a0responsabilidad \u00a0penal \u00a0es \u00a0de acto y no de autor, en el hipot\u00e9tico caso de que \u00a0hubiese \u00a0existido \u00a0intenci\u00f3n \u00a0criminal \u00a0en \u00a0la \u00a0mente del occiso al salir de la \u00a0cantina \u00a0 donde \u00a0 se \u00a0 encontraba, \u00a0 tal \u00a0prop\u00f3sito \u00a0no \u00a0trascendi\u00f3 \u00a0al \u00a0mundo \u00a0fenomenol\u00f3gico, \u00a0por \u00a0lo \u00a0que \u00a0dentro \u00a0del \u00a0contexto \u00a0f\u00e1ctico de la situaci\u00f3n \u00a0averiguada \u00a0no se dieron ni la actualidad ni la inminencia de una agresi\u00f3n ante \u00a0la \u00a0cual \u00a0deb\u00eda responder el procesado, sino que todo tuvo desarrollo dentro de \u00a0una \u00a0particular \u00a0situaci\u00f3n \u00a0en la que los contendientes se batieron en duelo en \u00a0igualdad \u00a0de \u00a0condiciones, \u00a0previa \u00a0disputa verbal iniciada por Wilson, de quien \u00a0tambi\u00e9n \u00a0 dedujo \u00a0el \u00a0juzgador \u00a0fue \u00a0el \u00a0primero \u00a0en \u00a0esgrimir \u00a0un \u00a0arma \u00a0y \u00a0en \u00a0disparar. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0As\u00ed \u00a0las \u00a0cosas, \u00a0las \u00a0atestaciones \u00a0tra\u00eddas \u00a0por el accionante no \u00a0aportan \u00a0ning\u00fan \u00a0elemento nuevo que por desconocido durante las instancias, por \u00a0razones \u00a0de \u00a0justicia, \u00a0sea \u00a0menester \u00a0revisar el fallo ejecutoriado para ver de \u00a0concluir \u00a0si \u00a0debe \u00a0sucumbir \u00a0la \u00a0responsabilidad \u00a0que \u00a0le \u00a0fuera \u00a0endilgada \u00a0al \u00a0inculpado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0este \u00a0orden \u00a0de ideas, como aquellos elementos de convicci\u00f3n no \u00a0alteran \u00a0la \u00a0esencia \u00a0del \u00a0juicio, \u00a0lo \u00a0que \u00a0se plantea es un tema ya debatido y \u00a0decidido, \u00a0por \u00a0lo \u00a0que \u00a0la presunci\u00f3n de acierto y legalidad del fallo atacado \u00a0permanece \u00a0inc\u00f3lume, \u00a0sin \u00a0que \u00a0la \u00a0impropiedad \u00a0en \u00a0que \u00a0tambi\u00e9n \u00a0incurre \u00a0el \u00a0demandante \u00a0al \u00a0atreverse \u00a0a \u00a0medir \u00a0el grado de credibilidad que en su opini\u00f3n \u00a0merecen \u00a0los \u00a0testimonios \u00a0arrimados \u00a0al \u00a0proceso \u00a0-por ejemplo el de Enith, que \u00a0califica \u00a0de \u00a0inducido-, \u00a0pueda \u00a0tampoco \u00a0concitar \u00a0la \u00a0apertura del tr\u00e1mite de \u00a0revisi\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Por \u00a0lo \u00a0anterior, \u00a0ante las deficiencias de que se duele el libelo, \u00a0se impone su rechazo de plano. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de lo expuesto, la CORTE SUPREMA DE JUSTICIA, SALA DE CASACI\u00d3N PENAL \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01. \u00a0Reconocer \u00a0personer\u00eda \u00a0al Dr. Gerardo \u00a0Castrill\u00f3n \u00a0Quintero \u00a0en \u00a0los \u00a0t\u00e9rminos del poder conferido por el sentenciado \u00a0WILSON MONROY GAIT\u00c1N. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02. \u00a0 RECHAZAR \u00a0IN \u00a0LIMINE \u00a0la \u00a0demanda \u00a0de \u00a0revisi\u00f3n \u00a0presentada \u00a0contra \u00a0los \u00a0fallos \u00a0de \u00a0primera y segunda instancias, de \u00a0fecha, \u00a0 naturaleza \u00a0 y \u00a0 origen \u00a0 indicados \u00a0 en \u00a0 la \u00a0 parte \u00a0motiva \u00a0de \u00a0este \u00a0prove\u00eddo. \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>C\u00d3PIESE, NOTIF\u00cdQUESE Y C\u00daMPLASE \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>EDGAR LOMBANA TRUJILLO \u00a0<\/p>\n<p>FERNANDO \u00a0 ARBOLEDA \u00a0 RIPOLL \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0JORGE \u00a0 \u00a0E. \u00a0 \u00a0C\u00d3RDOBA \u00a0 \u00a0POVEDA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 A. \u00a0 G\u00c1LVEZ \u00a0ARGOTE \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 JORGE AN\u00cdBAL \u00a0GOMEZ GALLEGO \u00a0\u00a0<\/p>\n<p>MARIO \u00a0 \u00a0MANTILLA \u00a0 NOUGUES \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0CARLOS \u00a0E. \u00a0MEJ\u00cdA \u00a0 \u00a0 ESCOBAR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>ALVARO \u00a0ORLANDO P\u00c9REZ PINZ\u00d3N \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 NILSON PINILLA PINILLA \u00a0\u00a0<\/p>\n<p>TERESA RUIZ NU\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso N\u00b0 15189 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente \u00a0 Dr. JORGE AN\u00cdBAL G\u00d3MEZ GALLEGO \u00a0 Aprobado Acta No. 38 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Santaf\u00e9 de Bogot\u00e1, D.C, catorce de marzo de dos mil. \u00a0\u00a0 VISTOS \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0De \u00a0acuerdo \u00a0con \u00a0lo \u00a0previsto \u00a0en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3111","post","type-post","status-publish","format-standard","hentry","category-8"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/3111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=3111"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/3111\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=3111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=3111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=3111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}