{"id":30901,"date":"2023-09-13T17:36:55","date_gmt":"2023-09-13T17:36:55","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap2824-201543258\/"},"modified":"2023-09-13T17:36:55","modified_gmt":"2023-09-13T17:36:55","slug":"ap2824-201543258","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap2824-201543258\/","title":{"rendered":"AP2824-2015(43258)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>AP2824-2015 \u00a0<\/p>\n<p>Radicaci\u00f3n N\u00b0. 43258 \u00a0<\/p>\n<p>(Aprobado Acta N\u00b0. 184) \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D.C., \u00a0veinticinco (25) de mayo de \u00a0dos mil quince (2015). \u00a0\u00a0<\/p>\n<p>MOTIVO DE LA DECISI\u00d3N \u00a0<\/p>\n<p>Decide \u00a0la Sala si es procedente admitir las \u00a0demandas \u00a0 de \u00a0 casaci\u00f3n \u00a0 presentadas \u00a0 por \u00a0 el \u00a0 defensor \u00a0 de \u00a0Yady \u00a0 Marilyn \u00a0Chamorro \u00a0L\u00f3pez \u00a0y \u00a0el representante de la Fiscal\u00eda, \u00a0contra \u00a0la \u00a0sentencia \u00a0proferida \u00a0el \u00a025 \u00a0de \u00a0noviembre \u00a0de 2013 por el Tribunal \u00a0Superior \u00a0de Pereira, que confirm\u00f3 parcialmente la dictada por el Juzgado Penal \u00a0del \u00a0Circuito \u00a0Adjunto \u00a0de la misma ciudad y conden\u00f3 a la procesada como autora \u00a0del \u00a0delito \u00a0de captaci\u00f3n masiva y habitual de dineros, en tanto que mantuvo la \u00a0absoluci\u00f3n \u00a0 \u00a0respecto \u00a0 del \u00a0 injusto \u00a0 de \u00a0 lavado \u00a0 de \u00a0 activos. \u00a0\u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>A \u00a0ra\u00edz \u00a0de \u00a0la \u00a0denuncia instaurada por el \u00a0Secretario \u00a0de \u00a0Gobierno \u00a0Municipal \u00a0de Pereira, Jhon Diego Molina, acerca de la \u00a0posible \u00a0conducta \u00a0delictiva \u00a0de captaci\u00f3n masiva y habitual de dineros, en esa \u00a0ciudad, \u00a0por \u00a0parte \u00a0de \u00a0la \u00a0empresa \u00a0denominada \u00a0Proyecciones \u00a0y \u00a0Comercializadora \u00a0DRFE, \u00a0la Fiscal\u00eda pudo \u00a0establecer, \u00a0a \u00a0trav\u00e9s de programa metodol\u00f3gico, que el representante legal de \u00a0esa \u00a0 firma, \u00a0 Carlos \u00a0 Alfredo \u00a0Su\u00e1rez, \u00a0hab\u00eda \u00a0abierto \u00a0oficinas \u00a0en \u00a0varios \u00a0departamentos \u00a0del \u00a0pa\u00eds \u00a0y \u00a0que \u00a0dicha \u00a0actividad \u00a0la inici\u00f3 en el 2005 en la \u00a0ciudad \u00a0de \u00a0Pasto, al tiempo que pretendi\u00f3 legalizarla desde el 11 de noviembre \u00a0de \u00a02007, \u00a0inscribiendo \u00a0en \u00a0C\u00e1mara \u00a0de \u00a0Comercio \u00a074 \u00a0sedes, \u00a0donde se captaba \u00a0dinero. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0As\u00ed \u00a0 mismo, \u00a0 que \u00a0la \u00a0firma \u00a0contaba \u00a0con \u00a027 \u00a0franquiciados, \u00a037 \u00a0administradores \u00a0y \u00a029 \u00a0asesores \u00a0externos; \u00a0conced\u00eda \u00a0franquicias a diferentes \u00a0personas, \u00a0a \u00a0quienes \u00a0se les requer\u00eda el 90% de sus recaudos y se beneficiaban \u00a0del 10% restante. \u00a0\u00a0<\/p>\n<p>Aqu\u00e9l \u00a0dinero \u00a0llegaba \u00a0a \u00a0manos de Su\u00e1rez \u00a0quien \u00a0 \u00a0lo \u00a0 \u00a0trasladaba \u00a0 \u00a0a \u00a0 \u00a0la \u00a0 \u00a0comercializadora \u00a0 para \u00a0 legalizar \u00a0 su \u00a0procedencia. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Con \u00a0ese \u00a0objetivo, \u00a0la empresa adquir\u00eda bienes muebles e inmuebles \u00a0con \u00a0apoyo \u00a0del personal franquiciado, administradores, dependientes y asesores, \u00a0entre \u00a0ellos, \u00a0Yady Marilyn Chamorro L\u00f3pez. \u00a0\u00a0<\/p>\n<p>Espec\u00edficamente, \u00a0a \u00a0la procesada se le se\u00f1ala de haber \u00a0participado \u00a0en \u00a0labores \u00a0donde \u00a0daba \u00a0a \u00a0conocer \u00a0la \u00a0empresa, captaba dineros, \u00a0exhib\u00eda \u00a0bienes \u00a0muebles \u00a0que \u00a0el \u00a0p\u00fablico \u00a0pod\u00eda \u00a0adquirir invirtiendo en la \u00a0empresa \u00a0DRFE, \u00a0en \u00a0las \u00a0sedes \u00a0de T\u00faquerres e Ipiales, donde su hermana Sandra \u00a0Patricia Chamorro L\u00f3pez era franquiciada y administradora. \u00a0\u00a0<\/p>\n<p>La \u00a0 actividad \u00a0realizada \u00a0por \u00a0Yady \u00a0Marilyn \u00a0inici\u00f3 en mayo de 2008 y \u00a0culmin\u00f3 \u00a0el \u00a011 \u00a0de noviembre de ese a\u00f1o, recibiendo como contraprestaci\u00f3n la \u00a0suma de $2.500.000.oo. \u00a0\u00a0<\/p>\n<p>Tambi\u00e9n \u00a0se \u00a0pudo \u00a0establecer \u00a0que \u00a0para la \u00a0\u00faltima \u00a0fecha, la implicada prestaba sus servicios a la Fiscal\u00eda General de la \u00a0Naci\u00f3n, \u00a0donde \u00a0se \u00a0desempe\u00f1aba \u00a0como \u00a0asistente \u00a0de \u00a0la \u00a0Fiscal\u00eda \u00a0Local \u00a0II \u00a0CAVIF. \u00a0\u00a0<\/p>\n<p>ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>1. \u00a0El \u00a01\u00ba \u00a0de \u00a0junio \u00a0de \u00a02009, \u00a0 ante \u00a0 el \u00a0 Juzgado \u00a0S\u00e9ptimo \u00a0Penal \u00a0Municipal \u00a0de \u00a0Pereira \u00a0con funciones de control de garant\u00edas, se llev\u00f3 a cabo \u00a0audiencia \u00a0 preliminar \u00a0 de \u00a0formulaci\u00f3n \u00a0de \u00a0imputaci\u00f3n \u00a0contra \u00a0Yadi \u00a0 Marilyn \u00a0Chamorro \u00a0L\u00f3pez, \u00a0por \u00a0el \u00a0delito \u00a0de \u00a0captaci\u00f3n \u00a0masiva \u00a0y habitual de dineros, en concurso con lavado de \u00a0activos \u00a0 \u00a0y \u00a0 \u00a0asesoramiento \u00a0 \u00a0y \u00a0 \u00a0otras \u00a0 actuaciones \u00a0 ilegales1. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a02. \u00a0La \u00a0Fiscal\u00eda 24 Seccional present\u00f3 el escrito de acusaci\u00f3n el \u00a02 \u00a0de julio de 2009, por las conductas punibles objeto de imputaci\u00f3n, previstas \u00a0en \u00a0los \u00a0art\u00edculos \u00a0316, 323 y 421 del C\u00f3digo Penal, en concurso heterog\u00e9neo, \u00a0con \u00a0la circunstancia de mayor punibilidad consagrada en el numeral 10 del canon \u00a058 \u00a0 \u00a0 \u00a0 ejusdem2. \u00a0La \u00a0audiencia \u00a0respectiva se \u00a0llev\u00f3 \u00a0a \u00a0cabo \u00a0el \u00a0d\u00eda 15 siguiente, bajo la direcci\u00f3n del Juez \u00danico Penal \u00a0del \u00a0Circuito \u00a0Especializado \u00a0de \u00a0conocimiento \u00a0de \u00a0la \u00a0misma ciudad3. \u00a0\u00a0<\/p>\n<p>3. \u00a0Celebrada la audiencia preparatoria, por \u00a0disposici\u00f3n \u00a0 del \u00a0 Acuerdo \u00a0 PSA \u00a0 \u2013 \u00a0A 11-8191 del 16 de junio de 2011, el asunto pas\u00f3 al conocimiento \u00a0del \u00a0Juzgado \u00a0Penal \u00a0del Circuito Especializado Adjunto de Pereira, despacho que \u00a0agot\u00f3 \u00a0el juicio oral y en la \u00faltima sesi\u00f3n, realizada el 18 de septiembre de \u00a02012, \u00a0 anunci\u00f3 \u00a0 sentido \u00a0 de \u00a0fallo \u00a0absolutorio4. \u00a0\u00a0<\/p>\n<p>El \u00a04 \u00a0de \u00a0octubre \u00a0del \u00a0mismo \u00a0a\u00f1o, dict\u00f3 \u00a0sentencia \u00a0en \u00a0la \u00a0que \u00a0absolvi\u00f3 \u00a0a \u00a0la enjuiciada de los delitos de captaci\u00f3n \u00a0masiva \u00a0y \u00a0habitual \u00a0de \u00a0dineros \u00a0y \u00a0lavado de activos, en tanto que declar\u00f3 la \u00a0prescripci\u00f3n \u00a0 frente \u00a0 al \u00a0 injusto \u00a0 de \u00a0asesoramiento \u00a0y \u00a0otras \u00a0actuaciones \u00a0ilegales5. \u00a0\u00a0<\/p>\n<p>4. \u00a0El \u00a0Tribunal \u00a0Superior de esa ciudad, al \u00a0conocer \u00a0 del \u00a0 recurso \u00a0de \u00a0apelaci\u00f3n \u00a0incoado \u00a0por \u00a0la \u00a0Fiscal\u00eda, \u00a0confirm\u00f3 \u00a0parcialmente \u00a0 la \u00a0decisi\u00f3n \u00a0del \u00a0A \u00a0quo, \u00a0en \u00a0cuanto \u00a0revoc\u00f3 \u00a0la absoluci\u00f3n dispuesta en relaci\u00f3n con el \u00a0delito \u00a0de \u00a0captaci\u00f3n masiva y habitual de dineros. En consecuencia, conden\u00f3 a \u00a0Yady \u00a0 \u00a0Marilyn \u00a0 \u00a0Chamorro \u00a0 \u00a0L\u00f3pez \u00a0 como \u00a0coautora \u00a0de \u00a0ese \u00a0il\u00edcito \u00a0a \u00a0la pena de cincuenta y un (51) \u00a0meses \u00a0y un (1) d\u00eda de prisi\u00f3n, multa de doce mil quinientos (12.500) salarios \u00a0m\u00ednimos \u00a0legales \u00a0mensuales \u00a0vigentes y la accesoria de inhabilitaci\u00f3n para el \u00a0ejercicio \u00a0de \u00a0derechos \u00a0y \u00a0funciones \u00a0p\u00fablicas \u00a0por tiempo igual a la sanci\u00f3n \u00a0principal. \u00a0\u00a0<\/p>\n<p>Le \u00a0neg\u00f3 \u00a0la \u00a0suspensi\u00f3n condicional de la \u00a0ejecuci\u00f3n \u00a0de \u00a0la \u00a0pena \u00a0y la prisi\u00f3n domiciliaria6. \u00a0\u00a0<\/p>\n<p>LAS DEMANDAS \u00a0<\/p>\n<p>1. \u00a0El defensor formula dos cargos contra la \u00a0sentencia \u00a0del \u00a0Tribunal, \u00a0no sin antes precisar que la finalidad del recurso es \u00a0el \u00a0respeto \u00a0de \u00a0las garant\u00edas fundamentales de su prohijada, la reparaci\u00f3n de \u00a0los \u00a0agravios \u00a0ocasionados \u00a0a \u00a0\u00e9sta y la efectividad del derecho material, toda \u00a0vez \u00a0que la decisi\u00f3n de segunda instancia se dict\u00f3 cuando ya hab\u00eda operado el \u00a0fen\u00f3meno \u00a0 de \u00a0 la \u00a0 prescripci\u00f3n \u00a0 y \u00a0 se \u00a0 desconoci\u00f3 \u00a0 el \u00a0 principio \u00a0 de \u00a0congruencia. \u00a0\u00a0<\/p>\n<p>Tambi\u00e9n \u00a0resulta \u00fatil para la unificaci\u00f3n \u00a0de \u00a0 la \u00a0 jurisprudencia \u00a0 en \u00a0 punto \u00a0 de \u00a0 la \u00a0 lex \u00a0tertia, \u00a0 en \u00a0virtud \u00a0de \u00a0la \u00a0reciente \u00a0modificaci\u00f3n \u00a0introducida por la Ley 1709 de 2014. \u00a0\u00a0<\/p>\n<p>Primero. \u00a0<\/p>\n<p>Anuncia que, seg\u00fan lo demanda la t\u00e9cnica de \u00a0casaci\u00f3n, \u00a0se \u00a0apoya en la causal segunda para reprochar el desconocimiento del \u00a0principio \u00a0de \u00a0congruencia, \u00a0pero \u00a0su \u00a0demostraci\u00f3n \u00a0la \u00a0hace \u00a0conforme \u00a0a \u00a0los \u00a0par\u00e1metros \u00a0 que \u00a0 gobiernan \u00a0 el \u00a0motivo \u00a0primero, \u00a0pues, \u00a0en \u00a0este \u00a0caso, \u00a0el \u00a0sentenciador \u00a0aplic\u00f3 \u00a0indebidamente \u00a0los \u00a0art\u00edculos 58-10, 60 y 63 del C\u00f3digo \u00a0Penal, y 448 del C\u00f3digo de Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>Recuerda \u00a0que \u00a0la \u00a0acusaci\u00f3n \u00a0es \u00a0el \u00a0marco \u00a0f\u00e1ctico \u00a0y \u00a0jur\u00eddico al que queda atado el funcionario judicial y cuando \u00e9ste \u00a0atribuye \u00a0hechos, \u00a0delitos \u00a0o \u00a0cargos no contemplados all\u00ed, desconoce el debido \u00a0proceso y el derecho a la defensa. \u00a0\u00a0<\/p>\n<p>En \u00a0 el \u00a0 sub \u00a0examine, \u00a0 la \u00a0Fiscal\u00eda, \u00a0no \u00a0obstante \u00a0atribuir \u00a0la \u00a0circunstancia \u00a0de mayor punibilidad prevista en el numeral 10\u00ba del art\u00edculo 58 \u00a0del \u00a0C\u00f3digo \u00a0Penal, \u00a0no \u00a0lo hizo en los alegatos de clausura y, sin embargo, el \u00a0Tribunal \u00a0dedujo \u00a0su \u00a0existencia \u00a0al \u00a0momento \u00a0de dosificar la pena, con lo cual \u00a0super\u00f3 \u00a0el \u00a0requisito \u00a0objetivo \u00a0consagrado \u00a0en \u00a0el \u00a0art\u00edculo \u00a063 \u00a0de la misma \u00a0normativa, \u00a0 para \u00a0 la \u00a0 procedencia \u00a0 de \u00a0 la \u00a0suspensi\u00f3n \u00a0condicional \u00a0de \u00a0la \u00a0pena. \u00a0\u00a0<\/p>\n<p>En orden a la correcci\u00f3n del yerro, se debe \u00a0redosificar \u00a0 \u00a0la \u00a0 \u00a0pena \u00a0 \u00a0impuesta \u00a0 \u00a0a \u00a0 Chamorro \u00a0L\u00f3pez, \u00a0y \u00a0analizar \u00a0la \u00a0procedencia \u00a0del \u00a0subrogado \u00a0atendiendo, \u00a0por \u00a0favorabilidad, \u00a0a la Ley 1709 de 2014, sin que para el efecto, \u00a0se \u00a0pueda \u00a0aplicar \u00a0el \u00a0art\u00edculo \u00a068 \u00a0A, \u00a0porque \u00a0ello supondr\u00eda darle efectos \u00a0retroactivos a una norma desfavorable. \u00a0\u00a0<\/p>\n<p>Apunta que para el momento de los hechos, el \u00a0original \u00a0precepto \u00a068 A, sin la modificaci\u00f3n de la aludida ley, no inclu\u00eda el \u00a0delito de captaci\u00f3n masiva y habitual de dineros. \u00a0\u00a0<\/p>\n<p>En \u00a0virtud \u00a0del \u00a0principio \u00a0conocido \u00a0como \u00a0lex \u00a0tertia, el actor es del \u00a0criterio que su asistida es acreedora del beneficio en comento. \u00a0\u00a0<\/p>\n<p>En \u00a0 ese \u00a0sentido, \u00a0solicita \u00a0se \u00a0case \u00a0la \u00a0sentencia. \u00a0\u00a0<\/p>\n<p>Segundo \u00a0 \u00a0 \u00a0 \u00a0 (subsidiario). \u00a0\u00a0<\/p>\n<p>Con estribo en la causal primera de casaci\u00f3n \u00a0reprocha \u00a0la violaci\u00f3n directa de la ley por aplicaci\u00f3n indebida del art\u00edculo \u00a029 \u00a0del \u00a0C\u00f3digo \u00a0Penal \u00a0y \u00a0falta \u00a0de aplicaci\u00f3n de los preceptos 30, 60-5 y 83 \u00a0ejusdem. \u00a0\u00a0<\/p>\n<p>Advierte \u00a0que \u00a0formula \u00a0este \u00a0reproche \u00a0como \u00a0subsidiario \u00a0y \u00a0que, \u00a0de \u00a0prosperar, \u00a0habr\u00eda \u00a0lugar \u00a0a \u00a0reconocer y declarar la \u00a0extinci\u00f3n de la acci\u00f3n penal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Conforme \u00a0a \u00a0la t\u00e9cnica que impone la demostraci\u00f3n de un cargo por \u00a0la \u00a0v\u00eda \u00a0directa, \u00a0de los hechos imputados y que el Tribunal entiende probados, \u00a0los \u00a0cuales \u00a0previamente \u00a0resume \u00a0a \u00a0su manera, deriva que, si no hubo un aporte \u00a0esencial \u00a0de \u00a0Yadi Marilyn Chamorro L\u00f3pez en \u00a0los \u00a0actos \u00a0desplegados \u00a0por \u00a0la \u00a0organizaci\u00f3n DRFE, debi\u00f3 ser \u00a0llamada a responder en calidad de c\u00f3mplice y no como coautora. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Y \u00a0si \u00a0se \u00a0dijera que tal argumento se refiere al lavado de activos, \u00a0ello \u00a0no \u00a0es \u00a0cierto porque frente a dicho cargo se absolvi\u00f3 a la encartada por \u00a0duda, \u00a0es \u00a0decir, \u00a0que \u00a0el fallador de segundo grado no encontr\u00f3 pruebas que la \u00a0involucraran \u00a0en \u00a0ninguna de las acciones alternativas previstas en el art\u00edculo \u00a0323 \u00a0del C\u00f3digo Penal \u00abporque si hubiera deducido un \u00a0aporte \u00a0no \u00a0esencial en las conductas all\u00ed descritas lo procedente era condenar \u00a0pero \u00a0 \u00a0 \u00a0degradando \u00a0 \u00a0 la \u00a0 \u00a0 participaci\u00f3n \u00a0 \u00a0 a \u00a0 \u00a0 c\u00f3mplice\u00bb. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0La \u00a0aplicaci\u00f3n \u00a0indebida \u00a0del canon 29 -2 de la misma normativa, se \u00a0concreta \u00a0en \u00a0que \u00a0no se cumple el presupuesto de esencialidad del aporte en los \u00a0actos \u00a0de \u00a0captaci\u00f3n \u00a0atribuidos \u00a0a \u00a0la enjuiciada, sino que, como lo dedujo el \u00a0fallador, \u00a0 \u00a0\u00abla \u00a0 esporadicidad, \u00a0 accidentalidad, \u00a0accesoriedad, \u00a0no \u00a0esencialidad de aporte de mi mandante la ubican en condici\u00f3n \u00a0de \u00a0 \u00a0part\u00edcipe \u00a0 \u00a0\u2013 \u00a0c\u00f3mplice\u00bb \u00a0conforme \u00a0al \u00a0inciso \u00a0 3\u00ba \u00a0 del \u00a0 art\u00edculo \u00a030 \u00a0de \u00a0la \u00a0misma \u00a0normativa, \u00a0excluido \u00a0por \u00a0el \u00a0fallador. \u00a0\u00a0<\/p>\n<p>Precepto que consagra una rebaja punitiva de \u00a0una \u00a0sexta \u00a0parte \u00a0a \u00a0la \u00a0mitad, por lo cual la sanci\u00f3n a imponer, siguiendo la \u00a0regla \u00a0prevista \u00a0en \u00a0el \u00a0numeral 5\u00ba del art\u00edculo 60, ser\u00eda de 16 a 90 meses y \u00a0multa de 41.666.66 s.m.l.m.v. \u00a0\u00a0<\/p>\n<p>Es \u00a0 \u00a0 \u00a0 \u00a0 decir, \u00a0que la acci\u00f3n penal, para ese delito, \u00a0prescribi\u00f3 \u00a0el \u00a028 de febrero de 2013, momento para el cual hab\u00eda transcurrido \u00a0la \u00a0mitad \u00a0del \u00a0m\u00e1ximo \u00a0punitivo, \u00a0esto \u00a0es, 45 meses, desde la formulaci\u00f3n de \u00a0imputaci\u00f3n \u00a0-1\u00ba \u00a0de \u00a0junio de 2009- conforme lo disponen los art\u00edculos 83 del \u00a0C\u00f3digo \u00a0 \u00a0Penal \u00a0 \u00a0y \u00a0 \u00a0292 \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0Ley \u00a0 \u00a0906 \u00a0 \u00a0de \u00a0 \u00a02004. \u00a0\u00a0<\/p>\n<p>En \u00a0consecuencia, \u00a0la \u00a0sentencia \u00a0de segunda \u00a0instancia \u00a0se \u00a0dict\u00f3 el 22 de noviembre de 2013, cuando la acci\u00f3n penal estaba \u00a0prescrita. \u00a0\u00a0<\/p>\n<p>Solicita se case la sentencia recurrida y, en \u00a0su \u00a0lugar, \u00a0se \u00a0declare \u00a0la extinci\u00f3n de la acci\u00f3n penal por prescripci\u00f3n del \u00a0injusto \u00a0 previsto \u00a0 en \u00a0 el \u00a0canon \u00a0316 \u00a0del \u00a0compendio \u00a0sustantivo. \u00a0\u00a0<\/p>\n<p>2. \u00a0El representante de la Fiscal\u00eda formula \u00a0dos \u00a0cargos \u00a0contra \u00a0la \u00a0sentencia del Tribunal, con la pretensi\u00f3n de lograr la \u00a0efectividad \u00a0 \u00a0 del \u00a0 \u00a0 derecho \u00a0 \u00a0 material \u00a0 \u00a0 con \u00a0 \u00a0la \u00a0 \u00a0declaraci\u00f3n \u00a0 \u00a0de \u00a0responsabilidad, \u00a0en cabeza \u00a0de \u00a0la \u00a0acusada, \u00a0frente \u00a0al \u00a0punible \u00a0de \u00a0lavado \u00a0de \u00a0activos, \u00a0por el cual fue \u00a0absuelta. \u00a0\u00a0<\/p>\n<p>Primero. \u00a0<\/p>\n<p>Invoca la causal tercera de casaci\u00f3n y acusa \u00a0la \u00a0 \u00a0sentencia \u00a0 \u00a0\u00abpor \u00a0violaci\u00f3n \u00a0directa \u00a0de la ley sustancial, por v\u00eda indirecta, al darse un error \u00a0de \u00a0hecho por falso juicio de existencia material al omitir elementos obrantes y \u00a0practicados \u00a0en \u00a0juicio v\u00e1lidamente\u00bb, referentes a la \u00a0importancia \u00a0del aporte de la acusada frente a la conducta de lavado de activos. \u00a0\u00a0<\/p>\n<p>Opina \u00a0 el \u00a0censor \u00a0que \u00a0la \u00a0contribuci\u00f3n \u00a0realizada \u00a0por Yady Marilyn Chamorro L\u00f3pez, \u00a0 \u00a0frente \u00a0 \u00a0a \u00a0 la \u00a0 captaci\u00f3n \u00a0 de \u00a0dineros, \u00a0 \u00a0y \u00a0 \u00a0a \u00a0 la \u00a0comercializadora \u00a0DRFE, \u00a0s\u00ed \u00a0fue \u00a0esencial, \u00a0contrario \u00a0a \u00a0lo \u00a0expuesto \u00a0por el \u00a0Tribunal, \u00a0 que \u00a0 lo \u00a0 consider\u00f3 \u00a0 como \u00a0\u00abepisodios \u00a0circunstanciales\u00bb. \u00a0\u00a0<\/p>\n<p>Atribuye \u00a0la \u00a0ocurrencia del yerro en que no \u00a0valor\u00f3 \u00a0los \u00a0documentos \u00a0incorporados \u00a0al \u00a0juicio \u00a0por medio de los testimonios \u00a0rendidos \u00a0por \u00a0las \u00a0investigadoras \u00a0Carla \u00a0Cristina \u00a0Castro \u00a0Moscoso \u00a0y \u00a0Claudia \u00a0Patricia Reyes Salazar. \u00a0\u00a0<\/p>\n<p>La primera de ellas dio cuenta del proceso de \u00a0verificaci\u00f3n \u00a0que \u00a0realiz\u00f3 \u00a0acerca de las actividades que ven\u00eda desarrollando \u00a0DRFE \u00a0y \u00a0la \u00a0existencia de las oficinas en las ciudades de T\u00faquerres e Ipiales, \u00a0encontrando \u00a0 \u00a0 \u00a0que, \u00a0efectivamente, \u00a0 \u00a0all\u00ed \u00a0funcion\u00f3 \u00a0dicho \u00a0establecimiento, \u00a0el \u00a0que \u00a0era atribuido a la familia Chamorro \u00a0L\u00f3pez, \u00a0a \u00a0cargo \u00a0de \u00a0Sandra \u00a0Chamorro, \u00a0su \u00a0esposo, su mam\u00e1 y hermanos, entre \u00a0ellos, \u00a0 Yady \u00a0 Marilyn \u00a0Chamorro \u00a0L\u00f3pez. \u00a0\u00a0<\/p>\n<p>As\u00ed mismo, con ella se ingres\u00f3 una denuncia \u00a0entablada \u00a0por \u00a0la \u00a0acusada, \u00a0de \u00a0fecha \u00a024 \u00a0de julio de 2008, atribuy\u00e9ndose la \u00a0calidad \u00a0de asesora jur\u00eddica, debido a irregularidades en un documento privado, \u00a0que \u00a0no \u00a0fue \u00a0tenido \u00a0en \u00a0cuenta \u00a0por \u00a0el \u00a0fallador \u00a0de segunda instancia, donde \u00a0presuntamente \u00a0se \u00a0demuestra \u00a0la \u201cestrecha relaci\u00f3n \u00a0con la actividad judicializada\u201d\u00a0 \u00a0\u00a0<\/p>\n<p>Por su parte, la investigadora Reyes Salazar, \u00a0hizo \u00a0saber \u00a0que \u00a0tambi\u00e9n \u00a0desarroll\u00f3 \u00a0labores \u00a0de \u00a0verificaci\u00f3n acerca de la \u00a0existencia \u00a0del \u00a0fen\u00f3meno \u00a0DRFE, \u00a0realiz\u00f3 entrevistas y recuper\u00f3 documentos y \u00a0elementos \u00a0tecnol\u00f3gicos; \u00a0frente al organigrama, se\u00f1al\u00f3 como cabeza visible a \u00a0Carlos \u00a0Alfredo \u00a0Su\u00e1rez, \u00a0quien \u00a0asign\u00f3 \u00a0las \u00a0sedes \u00a0de Ipiales y T\u00faquerres a \u00a0Sandra y Jos\u00e9 Luis Chamorro. \u00a0\u00a0<\/p>\n<p>Tambi\u00e9n \u00a0 \u00a0indic\u00f3 \u00a0 que \u00a0 Yadi \u00a0Marilin \u00a0Chamorro, siendo funcionaria \u00a0de \u00a0la \u00a0Fiscal\u00eda, captaba dinero en esas mismas instalaciones y al exhib\u00edrsele \u00a0una \u00a0revista \u00a0publicitaria \u00a0de \u00a0la \u00a0actividad \u00a0de \u00a0DRFE, \u00a0se expres\u00f3 sobre ella \u00a0verificando su finalidad de promoci\u00f3n. \u00a0\u00a0<\/p>\n<p>Seg\u00fan \u00a0 el \u00a0 recurrente, \u00a0ese \u00a0documento, \u00a0incorporado \u00a0al \u00a0juicio, \u00a0\u00abmuestra \u00a0como \u00a0(sic) \u00a0las \u00a0actividades \u00a0de \u00a0la \u00a0comercializadora DRFE, era (sic) de tal relevancia, que era \u00a0p\u00fablicamente \u00a0reconocida \u00a0su \u00a0labor, \u00a0con \u00a0ella \u00a0se \u00a0ofrec\u00eda \u00a0(sic) \u00a0bienes \u00a0y \u00a0servicios \u00a0que buscaban dar apariencia de legalidad a la actividad de captaci\u00f3n \u00a0(sic) \u00a0 dineros \u00a0sin \u00a0autorizaci\u00f3n \u00a0de \u00a0la \u00a0autoridad \u00a0competente\u00bb. \u00a0\u00a0<\/p>\n<p>Recuerda \u00a0que \u00a0la \u00a0acusaci\u00f3n \u00a0refiere \u00a0una \u00a0coautor\u00eda \u00a0impropia \u00a0de \u00a0la \u00a0implicada, \u00a0junto \u00a0con \u00a0el \u00a0m\u00e1ximo creador Carlos \u00a0Alfredo \u00a0Su\u00e1rez, \u00a0quien \u00a0ya \u00a0fue \u00a0condenado \u00a0por \u00a0esa \u00a0actividad, donde aquella \u00a0participaba \u00a0en \u00a0su \u00a0doble condici\u00f3n de \u00abasesor\u00eda y \u00a0captaci\u00f3n \u00a0de \u00a0dineros\u00bb, \u00a0siendo clara la ejecuci\u00f3n \u00a0del \u00a0lavado \u00a0de \u00a0activos, sin que el desempe\u00f1o de Yady \u00a0Marilyn se pueda estimar insignificante. \u00a0\u00a0<\/p>\n<p>En \u00a0 punto \u00a0de \u00a0la \u00a0trascendencia, \u00a0aduce \u00a0que, en ausencia del yerro, \u00a0se \u00a0habr\u00eda \u00a0determinado \u00a0a \u00a0la \u00a0acusada \u00a0como una persona muy importante en las \u00a0actividades \u00a0de \u00a0la \u00a0captadora de dineros, no solo por su cercan\u00eda con los m\u00e1s \u00a0grandes \u00a0gestores del fen\u00f3meno piramidal, sino por el andamiaje organizativo de \u00a0su \u00a0grupo \u00a0familiar, \u00a0quienes \u00a0se \u00a0hicieron \u00a0a las sedes de recaudo de Ipilaes y \u00a0T\u00faquerres, \u00a0pudiendo captar dineros producto de una actividad il\u00edcita, incluso \u00a0en \u00a0la \u00a0sede \u00a0de \u00a0la \u00a0Fiscal\u00eda, \u00a0los \u00a0cuales \u00a0estuvieron \u00a0bajo \u00a0su dominio para \u00a0adquirirlos, custodiarlos y transportarlos a su destino final. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0se \u00a0demostr\u00f3 \u00a0que \u00a0la \u00a0acusada \u00a0particip\u00f3 \u00a0en \u00a0una \u00a0feria \u00a0en el Colegio San Francisco de As\u00eds, donde tambi\u00e9n \u00a0capt\u00f3 dineros del p\u00fablico. \u00a0\u00a0<\/p>\n<p>Segundo \u00a0 \u00a0 \u00a0 cargo. \u00a0\u00a0<\/p>\n<p>En \u00a0el \u00a0marco de la misma causal tercera de \u00a0casaci\u00f3n, \u00a0acusa \u00a0a \u00a0la \u00a0sentencia \u00a0\u00abpor violaci\u00f3n \u00a0directa \u00a0de la ley sustancial, por v\u00eda indirecta al darse un error de hecho por \u00a0falso \u00a0 juicio \u00a0 de \u00a0 identidad \u00a0 al \u00a0 fraccionarse \u00a0 el \u00a0 contenido \u00a0probatorio \u00a0analizado\u00bb. \u00a0\u00a0<\/p>\n<p>Al \u00a0respecto, \u00a0se\u00f1ala \u00a0que el Tribunal s\u00ed \u00a0valoro \u00a0los \u00a0testimonios \u00a0de \u00a0V\u00edctor \u00a0Arturo Bastidas Bastidas y Carlos Alfredo \u00a0Su\u00e1rez \u00a0pero \u00a0parcel\u00f3 \u00a0su \u00a0contenido, \u00a0pues \u00a0ellos muestran la importancia del \u00a0aporte \u00a0de \u00a0la \u00a0acusada \u00a0y \u00a0la \u00a0dimensi\u00f3n \u00a0del fen\u00f3meno llamado Proyecciones y \u00a0Comercializadora DRFE. \u00a0\u00a0<\/p>\n<p>A \u00a0continuaci\u00f3n, \u00a0relaciona \u00a0apartes de la \u00a0declaraci\u00f3n \u00a0del \u00a0primero \u00a0de \u00a0ellos, \u00a0para \u00a0despu\u00e9s concluir que la implicada \u00a0ten\u00eda \u00a0dentro \u00a0de \u00a0sus \u00a0funciones la elaboraci\u00f3n del reglamento de trabajo, la \u00a0revisi\u00f3n \u00a0de \u00a0los contratos, que permit\u00edan el desarrollo de la actividad de la \u00a0empresa il\u00edcita. \u00a0\u00a0<\/p>\n<p>Enseguida, \u00a0resume \u00a0el contenido del testimonio de \u00a0Carlos \u00a0Alfredo Su\u00e1rez, cabeza de la empresa criminal, donde se hace referencia \u00a0a \u00a0las sedes de Ipiales y T\u00faquerres, que eran administradas por Sandra Chamorro \u00a0y \u00a0 su \u00a0grupo \u00a0familiar, \u00a0as\u00ed \u00a0como \u00a0al \u00a0papel \u00a0desempe\u00f1ado \u00a0por \u00a0la \u00a0acusada. \u00a0\u00a0<\/p>\n<p>Puntualiza \u00a0que \u00a0la valoraci\u00f3n, en su real \u00a0dimensi\u00f3n, \u00a0de \u00a0lo \u00a0declarado por Bastidas y Su\u00e1rez, hubiese llevado a inferir \u00a0la \u00a0 participaci\u00f3n \u00a0 de \u00a0 Yady \u00a0 Marilyn \u00a0en \u00a0el \u00a0delito \u00a0de \u00a0lavado \u00a0de \u00a0activos \u00a0y no \u00fanicamente en el de \u00a0captaci\u00f3n \u00a0 masiva \u00a0 y \u00a0habitual \u00a0como \u00a0se \u00a0estableci\u00f3 \u00a0en \u00a0la \u00a0sentencia \u00a0del \u00a0Ad quem. \u00a0\u00a0<\/p>\n<p>El \u00a0funcionario \u00a0recurrente \u00a0considera \u00a0que \u00a0tambi\u00e9n \u00a0se \u00a0parcel\u00f3 \u00a0la \u00a0declaraci\u00f3n rendida por Jhon Esteban Ortega Puertas \u00a0y, \u00a0de \u00a0los \u00a0apartes \u00a0que \u00a0extrae, \u00a0observa \u00a0que \u00a0el \u00a0Ad \u00a0quem fue muy restrictivo \u00a0al \u00a0momento \u00a0de \u00a0valorarlos, \u00a0porque \u00a0\u00fanicamente \u00a0refiri\u00f3 la acci\u00f3n de captar \u00a0dineros, \u00a0cuando \u00a0el \u00a0mismo \u00a0dej\u00f3 \u00a0claro \u00a0que \u00a0la \u00a0enjuiciada, \u00a0adicionalmente, \u00a0\u00able \u00a0 \u00a0 \u00a0generaba \u00a0 \u00a0 \u00a0confianza \u00a0 \u00a0 \u00a0a \u00a0 \u00a0 \u00a0los \u00a0inversionistas\u00bb \u00a0aduciendo \u00a0que \u00a0era \u00a0asesora \u00a0jur\u00eddica \u00a0de \u00a0la \u00a0empresa \u00a0y \u00a0que \u00a0su \u00a0mam\u00e1 \u00a0y \u00a0su \u00a0hermana \u00a0administraban las sedes atr\u00e1s mencionadas. \u00a0\u00a0<\/p>\n<p>De manera que, por su actividad, \u00a0 \u00a0 \u00a0 \u00a0necesariamente, \u00a0 \u00a0adquir\u00eda \u00a0 el \u00a0 dinero \u00a0 de \u00a0 los \u00a0inversionistas \u00a0y \u00a0lo \u00a0custodiaba \u00a0mientras \u00a0era \u00a0ingresado \u00a0a DRFE, en aquellas \u00a0sedes. \u00a0\u00a0<\/p>\n<p>M\u00e1s \u00a0 \u00a0 \u00a0 adelante, \u00a0asegura \u00a0el impugnante que, \u00a0con \u00a0el \u00a0testimonio \u00a0de Sandra Liliana \u00a0Arciniegas \u00a0se \u00a0puede \u00a0deducir \u00a0la \u00a0estrecha \u00a0vinculaci\u00f3n de la acusada con los \u00a0servicios \u00a0de \u00a0una comercializadora que aparentaba rasgos de legalidad, en tanto \u00a0que \u00a0Rita \u00a0Leonor \u00a0Estrada Salazar e Iv\u00e1n Dar\u00edo Moreno Chamorro confirmaron la \u00a0participaci\u00f3n \u00a0de \u00a0la \u00a0procesada \u00a0en una feria realizada por DRFE en el Colegio \u00a0San \u00a0Francisco de As\u00eds, desarrollada en el mes de octubre de 2008, junto con su \u00a0compa\u00f1ero \u00a0sentimental \u00a0\u00abrecaudando \u00a0dinero \u00a0en \u00a0la \u00a0feria \u00a0 \u00a0 \u00a0promocional \u00a0 \u00a0 de \u00a0 \u00a0 la \u00a0 \u00a0 comercializadora \u00a0 \u00a0 DRFE\u00bb. \u00a0\u00a0<\/p>\n<p>Todo esto con el fin de evidenciar el papel \u00a0protag\u00f3nico desempe\u00f1ado por la acusada en el lavado de activos. \u00a0\u00a0<\/p>\n<p>La \u00a0Fiscal\u00eda \u00a0concluye con la petici\u00f3n de \u00a0casar \u00a0parcialmente \u00a0la \u00a0sentencia \u00a0con \u00a0fecha \u00a0del \u00a025 \u00a0de \u00a0noviembre \u00a0de 2013, \u00a0proferida \u00a0por \u00a0el \u00a0Tribunal \u00a0Superior \u00a0de Distrito Judicial de Pereira y, en su \u00a0lugar, se condene a la enjuiciada por este delito. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0<\/p>\n<p>1. \u00a0En \u00a0el \u00a0contexto \u00a0de \u00a0la \u00a0regulaci\u00f3n \u00a0consagrada \u00a0en \u00a0la \u00a0Ley 906 de 2004, la finalidad del recurso de casaci\u00f3n, como \u00a0instrumento \u00a0de \u00a0control \u00a0constitucional \u00a0y \u00a0legal, radica en la efectividad del \u00a0derecho \u00a0material, \u00a0el \u00a0respeto \u00a0de \u00a0las \u00a0garant\u00edas \u00a0de \u00a0los intervinientes, la \u00a0reparaci\u00f3n \u00a0de \u00a0los \u00a0agravios \u00a0inferidos \u00a0a \u00a0estos \u00a0y \u00a0la \u00a0unificaci\u00f3n \u00a0de \u00a0la \u00a0jurisprudencia, \u00a0seg\u00fan \u00a0lo \u00a0disponen \u00a0los \u00a0art\u00edculos \u00a0180 \u00a0y \u00a0181 de la citada \u00a0normativa. \u00a0\u00a0<\/p>\n<p>Dada \u00a0la \u00a0naturaleza \u00a0extraordinaria \u00a0de la \u00a0impugnaci\u00f3n, \u00a0el \u00a0demandante \u00a0debe \u00a0comprobar \u00a0que \u00a0el \u00a0fallo \u00a0de \u00a0casaci\u00f3n es \u00a0necesario \u00a0para \u00a0el \u00a0cumplimiento \u00a0de \u00a0uno \u00a0de \u00a0estos objetivos y para ello debe \u00a0atender \u00a0a los requerimientos de coherencia, claridad y precisi\u00f3n, a trav\u00e9s de \u00a0una \u00a0 exposici\u00f3n \u00a0que \u00a0evidencie \u00a0la \u00a0vulneraci\u00f3n \u00a0de \u00a0derechos \u00a0o \u00a0garant\u00edas \u00a0fundamentales, \u00a0con \u00a0apoyo \u00a0en \u00a0la \u00a0causal respectiva, cuyo desarrollo impone el \u00a0respeto \u00a0a las reglas que rigen el recurso, so pena de ser inadmitido el libelo, \u00a0seg\u00fan lo dispone el art\u00edculo 184 -2. \u00a0\u00a0<\/p>\n<p>2. La demanda formulada por la defensa de la \u00a0procesada, \u00a0adolece \u00a0del soporte argumentativo necesario para alcanzar alguno de \u00a0los \u00a0fines \u00a0primordiales \u00a0del recurso y de su contenido no se advierte necesario \u00a0ejercer ese control constitucional y legal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0La \u00a0unificaci\u00f3n \u00a0de \u00a0la \u00a0jurisprudencia en punto de la lex \u00a0tertia \u00a0en \u00a0virtud \u00a0de \u00a0la \u00a0reciente \u00a0modificaci\u00f3n \u00a0de \u00a0la Ley 1709 de 2014, es un enunciado carente de demostraci\u00f3n \u00a0que, como se ver\u00e1, est\u00e1 atado a la prosperidad del primer cargo. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, en la proposici\u00f3n y desarrollo de \u00a0los \u00a0cargos \u00a0que \u00a0postula, no \u00a0se \u00a0ci\u00f1e \u00a0a \u00a0los \u00a0presupuestos \u00a0de l\u00f3gica y debida argumentaci\u00f3n inherentes a \u00a0cada una de las causales invocadas en el libelo. \u00a0\u00a0<\/p>\n<p>2.1. En relaci\u00f3n con el cargo primero, \u00a0se \u00a0debe \u00a0reconocer que el actor \u00a0acert\u00f3 \u00a0en \u00a0acudir \u00a0a \u00a0la \u00a0causal \u00a0segunda \u00a0del \u00a0art\u00edculo \u00a0181 \u00a0del C\u00f3digo de \u00a0Procedimiento \u00a0Penal de 2004, para acreditar el desconocimiento del principio \u00a0de \u00a0congruencia, \u00a0y \u00a0que en su \u00a0demostraci\u00f3n \u00a0atendiera \u00a0a \u00a0las \u00a0directrices \u00a0de la causal primera \u2013violaci\u00f3n \u00a0 directa-, \u00a0como \u00a0 igual \u00a0 se \u00a0puede \u00a0invocar \u00a0el \u00a0motivo \u00a0tercero \u00a0\u2013violaci\u00f3n \u00a0indirecta-, \u00a0seg\u00fan \u00a0el \u00a0caso, \u00a0tal \u00a0como \u00a0lo \u00a0viene \u00a0diciendo \u00a0la Sala de tiempo \u00a0atr\u00e1s \u00a0 \u00a0(CSJ \u00a0 \u00a0AP, \u00a0 \u00a005 \u00a0 \u00a0dic. \u00a0 \u00a02007, \u00a0 rad. \u00a028822): \u00a0\u00a0<\/p>\n<p>El \u00a0reparo \u00a0por \u00a0falta de congruencia debe \u00a0denunciarse \u00a0por \u00a0la \u00a0v\u00eda de la casual segunda de nulidad, pero sustentarse con \u00a0los \u00a0par\u00e1metros l\u00f3gicos que gobiernan alguna de las causales primera o tercera \u00a0de \u00a0casaci\u00f3n \u00a0de \u00a0la \u00a0Ley 906 de 2004, es decir, violaci\u00f3n directa o indirecta \u00a0del \u00a0bloque de constitucionalidad, de la Constituci\u00f3n o de una ley de contenido \u00a0sustancial \u00a0 porque \u00a0 \u201cpara \u00a0su \u00a0demostraci\u00f3n, \u00a0es \u00a0necesario \u00a0precisar \u00a0si \u00a0los \u00a0desaciertos se produjeron al momento de ubicar los \u00a0hechos \u00a0en \u00a0el \u00a0respectivo tipo penal o en el proceso de an\u00e1lisis y valoraci\u00f3n \u00a0de \u00a0las \u00a0pruebas, \u00a0y \u00a0adicionalmente \u00a0concretar \u00a0c\u00f3mo \u00a0se produjo el yerro, con \u00a0fundamento \u00a0en \u00a0las \u00a0directrices \u00a0propias \u00a0de la violaci\u00f3n directa o indirecta, \u00a0seg\u00fan \u00a0 \u00a0el \u00a0 \u00a0caso\u201d \u00a0\u201d7. \u00a0\u00a0<\/p>\n<p>Tambi\u00e9n \u00a0es \u00a0cierto \u00a0que la congruencia se \u00a0predica \u00a0de \u00a0la \u00a0correspondencia f\u00e1ctica, personal y jur\u00eddica que debe existir \u00a0entre \u00a0la \u00a0sentencia \u00a0y \u00a0la \u00a0acusaci\u00f3n, \u00a0sin que el juzgador pueda condenar por \u00a0delitos \u00a0por \u00a0los \u00a0que \u00a0el \u00a0fiscal \u00a0no haya solicitado condena, ni sorprender al \u00a0acusado \u00a0 por \u00a0 hechos \u00a0 frente \u00a0 a \u00a0 los \u00a0 cuales \u00a0 no \u00a0 tuvo \u00a0 oportunidad \u00a0de \u00a0defenderse. \u00a0\u00a0<\/p>\n<p>Ocurre, \u00a0 sin \u00a0 embargo, \u00a0que, \u00a0 \u00a0 en \u00a0 \u00a0 este \u00a0 \u00a0 caso, \u00a0 no \u00a0 se \u00a0 verifica \u00a0 la \u00a0 falta \u00a0 de \u00a0correspondencia \u00a0 que \u00a0se \u00a0reprocha \u00a0en \u00a0punto \u00a0de \u00a0la \u00a0circunstancia \u00a0de \u00a0mayor \u00a0punibilidad \u00a0prevista \u00a0en \u00a0el \u00a0numeral \u00a010\u00ba del art\u00edculo 58 del C\u00f3digo Penal, \u00a0porque \u00a0si \u00a0en \u00a0los \u00a0alegatos de clausura, \u00a0el \u00a0funcionario \u00a0del \u00a0ente \u00a0acusador \u00a0no hizo menci\u00f3n expresa del \u00a0precepto \u00a0o \u00a0de \u00a0la \u00a0causal \u00a0consistente \u00a0en \u00a0haber \u00a0obrado \u00a0en coparticipaci\u00f3n \u00a0criminal, lo cierto es que, f\u00e1cticamente, s\u00ed se refiri\u00f3 a ella. \u00a0\u00a0<\/p>\n<p>En \u00a0 efecto, \u00a0observa \u00a0la \u00a0Sala, \u00a0de \u00a0los \u00a0argumentos \u00a0expuestos por el Fiscal, en la audiencia de juicio oral celebrada el \u00a018 \u00a0de \u00a0septiembre \u00a0de 2012, refiri\u00f3, entre otros aspectos, que se trata de una \u00a0\u00abcaptaci\u00f3n \u00a0masiva \u00a0y \u00a0habitual \u00a0de \u00a0dinero \u00a0en \u00a0el \u00a0territorio \u00a0nacional \u00a0a \u00a0cargo \u00a0del \u00a0se\u00f1or \u00a0Carlos \u00a0Alfredo \u00a0Su\u00e1rez y de otras \u00a0personas \u00a0 \u00a0que, \u00a0 como \u00a0copart\u00edcipes, \u00a0en el caso \u00a0de \u00a0Yady \u00a0Marilyn Chamorro, coautora, desarrollaron en gran parte del territorio \u00a0nacional\u00bb8. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Esos t\u00e9rminos expuestos por el funcionario, \u00a0no \u00a0permiten \u00a0deducir, como lo hace el libelista, falta de congruencia, am\u00e9n de \u00a0la \u00a0formalidad \u00a0omitida, \u00a0m\u00e1xime \u00a0cuando \u00a0aqu\u00e9l solicit\u00f3 condena por las tres \u00a0conductas \u00a0que \u00a0fueron imputadas, acusadas y verificadas en el debate probatorio \u00a0del \u00a0 juicio9. \u00a0De \u00a0all\u00ed que ning\u00fan yerro se le pueda reprochar al Ad \u00a0quem \u00a0por \u00a0haber \u00a0tenido en cuenta la \u00a0aludida \u00a0 circunstancia, \u00a0 toda \u00a0 vez \u00a0 que \u00a0 guarda \u00a0 correspondencia \u00a0 con \u00a0la \u00a0imputaci\u00f3n10 \u00a0 \u00a0 \u00a0 y \u00a0 \u00a0 \u00a0 la \u00a0 \u00a0 \u00a0 acusaci\u00f3n11 y, de esa manera, lo plasm\u00f3 \u00a0en la sentencia. \u00a0\u00a0<\/p>\n<p>Si \u00a0bien \u00a0lo \u00a0dicho \u00a0hasta este momento, es \u00a0suficiente \u00a0para \u00a0inadmitir \u00a0el \u00a0reproche, \u00a0no sobra se\u00f1alar que la pretensi\u00f3n \u00a0supeditada \u00a0a \u00a0su \u00a0prosperidad, \u00a0encaminada \u00a0a \u00a0obtener \u00a0el reconocimiento de la \u00a0suspensi\u00f3n \u00a0de \u00a0la \u00a0ejecuci\u00f3n \u00a0de \u00a0la \u00a0pena, \u00a0en \u00a0virtud \u00a0de \u00a0la \u00a0lex \u00a0 tertia, \u00a0aplicando \u00a0por \u00a0favorabilidad \u00fanicamente el art\u00edculo \u00a029 \u00a0de \u00a0la \u00a0Ley \u00a01709 \u00a0de \u00a02014, \u00a0no \u00a0as\u00ed el canon 32 de esa normativa, sino el \u00a0original \u00a0art\u00edculo 68 A del C\u00f3digo Penal, no resulta novedosa, pues ya la Sala \u00a0en \u00a0CSJ AP2146 del 30 de abril de 2014, rad. 43256, se pronunci\u00f3 al respecto en \u00a0sentido negativo, por las siguientes razones: \u00a0\u00a0<\/p>\n<p>Como \u00a0lo \u00a0viene \u00a0recordando \u00a0la \u00a0Corte \u00a0en \u00a0recientes \u00a0decisiones, \u00a0si bien esta Sala ha admitido la denominada lex \u00a0tertia, \u00a0igualmente \u00a0ha \u00a0dicho \u00a0que \u00a0\u201cello \u00a0opera \u00a0en \u00a0circunstancias \u00a0muy particulares, \u00a0tambi\u00e9n \u00a0desarrolladas \u00a0ya \u00a0por \u00a0la \u00a0jurisprudencia \u00a0de la Sala (CSJ SP, 3 sep. \u00a02001, \u00a0rad. \u00a016837), \u00a0que refieren la posibilidad de realizar esa mixtura cuando \u00a0los \u00a0 preceptos \u00a0confrontados \u00a0remiten \u00a0a \u00a0institutos, \u00a0subrogados \u00a0o \u00a0sanciones \u00a0diferentes, \u00a0y \u00a0no \u00a0en los casos en que se busca aplicar un beneficio concreto a \u00a0partir \u00a0de \u00a0tomar \u00a0en \u00a0consideraci\u00f3n \u00a0elementos \u00a0disonantes \u00a0de \u00a0las diferentes \u00a0normatividades \u00a0en \u00a0juego\u201d \u00a0(CSJ SP, 12 de marz. de \u00a02014, rad. 42623; CSJ SP, 2 de abr. de 2014, rad. 43209). \u00a0\u00a0<\/p>\n<p>Por \u00a0eso, \u00a0como \u00a0lo \u00a0concluy\u00f3 de la misma \u00a0manera \u00a0la Corte en las determinaciones precitadas, tomar factores favorables de \u00a0una \u00a0y \u00a0otra \u00a0normatividades, \u00a0para \u00a0as\u00ed construir el beneficio o subrogado, no \u00a0solo \u00a0implica \u00a0una \u00a0suplantaci\u00f3n \u00a0ilegal del legislador, sino que finalmente la \u00a0combinaci\u00f3n \u00a0normativa \u00a0desnaturaliza \u00a0por \u00a0completo \u00a0la \u00a0figura del beneficio, \u00a0desdice \u00a0de \u00a0su \u00a0finalidad \u00a0y, \u00a0no \u00a0por \u00a0\u00faltimo \u00a0menos \u00a0importante, termina por \u00a0violentar el principio de igualdad. \u00a0\u00a0<\/p>\n<p>Conforme a lo expuesto, no resulta entonces \u00a0procedente, \u00a0pues \u00a0ello \u00a0supondr\u00eda \u00a0la \u00a0creaci\u00f3n \u00a0de una nueva ley, lo cual le \u00a0est\u00e1 \u00a0vedado \u00a0al \u00a0juzgador, \u00a0aplicar \u00a0el \u00a0art\u00edculo 29 de la Ley 1709 de 2014 e \u00a0inaplicar \u00a0el \u00a0art\u00edculo \u00a032 \u00a0de \u00a0la \u00a0misma \u00a0disposici\u00f3n \u00a0legal para conceder a \u00a0(\u2026) \u00a0 la \u00a0 condena \u00a0de \u00a0ejecuci\u00f3n condicional. \u00a0\u00a0<\/p>\n<p>La falta de raz\u00f3n del libelista impide que \u00a0el reproche pueda ser admitido. \u00a0\u00a0<\/p>\n<p>2.2. \u00a0 \u00a0 Frente \u00a0 \u00a0al \u00a0 \u00a0segundo \u00a0 cargo, \u00a0en \u00a0el \u00a0que \u00a0propone \u00a0la \u00a0violaci\u00f3n \u00a0directa de la ley sustancial, por aplicaci\u00f3n indebida del art\u00edculo \u00a029 \u00a0del \u00a0C\u00f3digo \u00a0Penal \u00a0y \u00a0falta \u00a0de aplicaci\u00f3n de los preceptos 30, 60-5 y 83 \u00a0ejusdem, tambi\u00e9n adolece de \u00a0los requerimientos necesarios para su admisi\u00f3n. \u00a0\u00a0<\/p>\n<p>Efectivamente, \u00a0 \u00a0 la \u00a0 \u00a0violaci\u00f3n \u00a0 directa \u00a0contempla \u00a0aquellos \u00a0errores \u00a0de selecci\u00f3n normativa en que puede incurrir el juzgador, entre ellos, \u00a0la \u00a0aplicaci\u00f3n indebida y la \u00a0falta \u00a0de \u00a0aplicaci\u00f3n \u00a0de \u00a0normas \u00a0de car\u00e1cter sustancial, caso en el cual, la discusi\u00f3n debe girar en el \u00a0plano \u00a0netamente \u00a0jur\u00eddico, admitiendo, sin reparos, la declaraci\u00f3n f\u00e1ctica y \u00a0probatoria \u00a0contenida \u00a0en \u00a0el \u00a0fallo, \u00a0pues se trata de demostrar que los hechos \u00a0establecidos \u00a0 no \u00a0encuentran \u00a0espacio \u00a0en \u00a0los \u00a0supuestos \u00a0contemplados \u00a0en \u00a0el \u00a0precepto. \u00a0\u00a0<\/p>\n<p>El \u00a0desarrollo de la censura desatiende tan \u00a0claras \u00a0previsiones, porque el letrado orienta su argumentaci\u00f3n a demostrar que \u00a0a \u00a0su \u00a0asistida \u00a0se \u00a0le debi\u00f3 condenar como c\u00f3mplice de la conducta punible de \u00a0captaci\u00f3n \u00a0 masiva \u00a0y \u00a0habitual \u00a0de \u00a0dinero, \u00a0pero \u00a0en \u00a0el \u00a0cometido \u00a0de \u00a0darle \u00a0consistencia \u00a0a su propuesta, interpreta a su acomodo algunas de las reflexiones \u00a0aducidas \u00a0por \u00a0la \u00a0colegiatura, postura que no sirve para demostrar el equ\u00edvoco \u00a0del \u00a0juzgador \u00a0por \u00a0aplicaci\u00f3n \u00a0indebida \u00a0y \u00a0falta de aplicaci\u00f3n de las normas \u00a0arriba se\u00f1aladas. \u00a0\u00a0<\/p>\n<p>Lo \u00a0anterior, \u00a0teniendo en cuenta que, como \u00a0bien \u00a0lo \u00a0reconoce \u00a0el \u00a0mismo \u00a0defensor, el argumento que trae a colaci\u00f3n, hace \u00a0relaci\u00f3n \u00a0al \u00a0examen \u00a0del \u00a0Tribunal destinado a establecer si la conducta de la \u00a0implicada \u00a0encaja \u00a0en \u00a0la conducta punible de lavado de activos y donde precis\u00f3 \u00a0\u00abnecesario \u00a0 \u00a0 considerar \u00a0 \u00a0 la \u00a0 \u00a0 esencialidad \u00a0de \u00a0la contribuci\u00f3n de la \u00a0se\u00f1ora \u00a0Yady \u00a0Marilyn Chamorro a la gigantesca defraudaci\u00f3n atribuida a Carlos \u00a0Alfredo \u00a0 \u00a0 Su\u00e1rez \u00a0 \u00a0y \u00a0 \u00a0su \u00a0 \u00a0grupo \u00a0 \u00a0DRFE\u00bb12, \u00a0aspecto \u00a0que \u00a0descart\u00f3 \u00a0tras \u00a0el \u00a0an\u00e1lisis \u00a0probatorio \u00a0pertinente. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Referente \u00a0argumentativo \u00a0que aprovecha para colegir, que si no hubo \u00a0un \u00a0 aporte \u00a0 esencial \u00a0 de \u00a0 su \u00a0asistida \u00a0en \u00a0los \u00a0actos \u00a0desplegados \u00a0por \u00a0la \u00a0organizaci\u00f3n, \u00a0 entonces, \u00a0debi\u00f3 \u00a0ser \u00a0llamada a responder como c\u00f3mplice y no como coautora del delito de \u00a0captaci\u00f3n masiva y habitual de dineros. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Adem\u00e1s, \u00a0contrariando abiertamente la dial\u00e9ctica del sentenciador, \u00a0niega \u00a0que \u00a0aqu\u00e9l argumento se refiera al lavado de activos porque frente a ese \u00a0injusto su defendida fue absuelta por duda. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Nada \u00a0m\u00e1s \u00a0desatinado \u00a0que \u00a0enrostrarle \u00a0al \u00a0juzgador \u00a0un \u00a0yerro de \u00a0selecci\u00f3n \u00a0normativa, \u00a0por \u00a0la \u00a0v\u00eda \u00a0directa, a partir de razonamientos que no \u00a0corresponden \u00a0al \u00a0verdadero \u00a0supuesto \u00a0f\u00e1ctico \u00a0probado, pues de esa manera, no \u00a0solo \u00a0se \u00a0desconoce el car\u00e1cter extraordinario del recurso, sino los principios \u00a0que \u00a0gobiernan \u00a0la casaci\u00f3n. Uno de ellos, el de correcci\u00f3n material, conforme \u00a0con \u00a0el \u00a0cual, \u00a0las \u00a0razones, \u00a0fundamento \u00a0y \u00a0contenido \u00a0de \u00a0la \u00a0censura, \u00a0deben \u00a0corresponder \u00a0en \u00a0un \u00a0todo \u00a0con \u00a0la realidad procesal (CSJ AP, 2 may. 2012. Rad. \u00a026846). \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0El \u00a0desafuero adquiere mayor dimensi\u00f3n, cuando, a rengl\u00f3n seguido, \u00a0en \u00a0clara \u00a0petici\u00f3n de principio, da por demostrada, sin estarlo, la calidad de \u00a0c\u00f3mplice \u00a0de \u00a0su \u00a0asistida \u00a0y \u00a0sobre \u00a0esa \u00a0base \u00a0proclama \u00a0que la acci\u00f3n penal \u00a0prescribi\u00f3 \u00a0el \u00a0pasado \u00a028 \u00a0de febrero de 2013, en virtud de la rebaja punitiva \u00a0prevista en el inciso 3\u00ba del art\u00edculo 30 del C\u00f3digo Penal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Con \u00a0semejante \u00a0postura, desatendi\u00f3 que la finalidad del recurso de \u00a0casaci\u00f3n \u00a0es doblegar la presunci\u00f3n de acierto y legalidad que ampara el fallo \u00a0recurrido, \u00a0prop\u00f3sito que s\u00f3lo se alcanza a partir de la presentaci\u00f3n l\u00f3gica \u00a0y \u00a0adecuada de cada causal y su correspondiente desarrollo, con demostraci\u00f3n de \u00a0su trascendencia en la parte resolutiva de la decisi\u00f3n. \u00a0\u00a0<\/p>\n<p>En esas condiciones, la censura no puede ser \u00a0admitida. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a03. \u00a0En \u00a0el \u00a0libelo \u00a0presentado por el representante de la Fiscal\u00eda, \u00a0tampoco \u00a0se \u00a0advierten \u00a0acreditados \u00a0los requisitos para su admisi\u00f3n, porque el \u00a0prop\u00f3sito \u00a0de \u00a0lograr \u00a0la \u00a0efectividad \u00a0del \u00a0derecho \u00a0material, es un enunciado \u00a0ausente de demostraci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Adicionalmente, \u00a0en \u00a0la formulaci\u00f3n de los cargos no se ci\u00f1e a las \u00a0reglas \u00a0que \u00a0rigen la impugnaci\u00f3n extraordinaria y en su desarrollo no acredita \u00a0alguno de los desaciertos que le atribuye al sentenciador. \u00a0\u00a0<\/p>\n<p>3.1. \u00a0En el primer \u00a0cargo, \u00a0acude \u00a0a \u00a0la \u00a0causal tercera de casaci\u00f3n para \u00a0acusar \u00a0la \u00a0sentencia \u00a0\u00abpor violaci\u00f3n directa de la \u00a0ley \u00a0sustancial, por v\u00eda indirecta, al darse un error de hecho por falso juicio \u00a0de \u00a0existencia \u00a0material \u00a0al \u00a0omitir \u00a0elementos obrantes y practicados en juicio \u00a0v\u00e1lidamente\u00bb. \u00a0\u00a0<\/p>\n<p>De \u00a0esa manera, involucra propuestas que se \u00a0repelen \u00a0entre \u00a0s\u00ed, \u00a0toda \u00a0vez \u00a0que \u00a0la violaci\u00f3n directa de la ley, indica la \u00a0incursi\u00f3n \u00a0de \u00a0alg\u00fan \u00a0yerro \u00a0netamente \u00a0jur\u00eddico, de aplicaci\u00f3n del derecho, \u00a0mientras \u00a0 que \u00a0 la \u00a0 violaci\u00f3n \u00a0 indirecta \u00a0refiere \u00a0aquellos \u00a0desaciertos \u00a0de \u00a0apreciaci\u00f3n probatoria en que puede incurrir el sentenciador. \u00a0\u00a0<\/p>\n<p>Por manera que, al tratar se asemejar ambas \u00a0categor\u00edas \u00a0de infracci\u00f3n a la ley, se incumple con los m\u00ednimos requisitos de \u00a0claridad \u00a0y coherencia que deben contener los reproches, en orden a demostrar la \u00a0real \u00a0ocurrencia \u00a0de \u00a0yerros \u00a0trascendentes \u00a0que atentan contra la legalidad del \u00a0fallo. \u00a0\u00a0<\/p>\n<p>De \u00a0otra \u00a0parte, \u00a0si \u00a0se \u00a0admitiera \u00a0que la \u00a0intenci\u00f3n \u00a0del \u00a0actor \u00a0fue \u00a0la \u00a0de acreditar el falso juicio de existencia, por \u00a0omisi\u00f3n \u00a0 que \u00a0menciona, \u00a0de \u00a0sus \u00a0argumentos \u00a0se \u00a0constata \u00a0que \u00a0no \u00a0asume \u00a0la \u00a0correspondiente \u00a0carga \u00a0demostrativa, \u00a0concretando \u00a0cu\u00e1l es la informaci\u00f3n que \u00a0brindan \u00a0los \u00a0elementos \u00a0objeto \u00a0de \u00a0censura, \u00a0as\u00ed como el m\u00e9rito demostrativo \u00a0correspondiente, \u00a0y \u00a0la manera c\u00f3mo un correcto an\u00e1lisis del acervo probatorio \u00a0incide \u00a0en \u00a0las \u00a0conclusiones \u00a0del \u00a0fallador, \u00a0a \u00a0tal \u00a0punto, que otra ser\u00eda la \u00a0orientaci\u00f3n de lo resuelto. \u00a0\u00a0<\/p>\n<p>El \u00a0simple \u00a0hecho \u00a0de \u00a0relacionar \u00a0aquellas \u00a0pruebas \u00a0 \u00a0 testimoniales \u00a0 \u00a0 y \u00a0 \u00a0 documentales, \u00a0 \u00a0para \u00a0 \u00a0inferir, \u00a0de \u00a0su \u00a0contenido, \u00a0la responsabilidad \u00a0penal \u00a0de \u00a0la \u00a0procesada, \u00a0frente al delito de lavado de activos por el cual fue \u00a0absuelta, \u00a0no pasa de ser un an\u00e1lisis subjetivo e interesado que apenas refleja \u00a0una \u00a0discrepancia \u00a0con el an\u00e1lisis probatorio efectuado por el sentenciador, el \u00a0cual \u00a0no \u00a0puede \u00a0ser \u00a0objeto \u00a0de \u00a0ataque en esta sede, salvo que se demuestre el \u00a0desconocimiento \u00a0de \u00a0los \u00a0postulados \u00a0de \u00a0la \u00a0sana \u00a0cr\u00edtica \u00a0y, en ese caso, es \u00a0preciso acudir al falso raciocinio. \u00a0\u00a0<\/p>\n<p>3.2. Las mismas falencias argumentativas se \u00a0evidencian \u00a0 \u00a0 en \u00a0 \u00a0 el \u00a0 \u00a0 segundo \u00a0 \u00a0cargo, \u00a0donde \u00a0nuevamente \u00a0contraviene \u00a0los \u00a0principios \u00a0l\u00f3gicos \u00a0y \u00a0t\u00e9cnicos \u00a0 que \u00a0 rigen \u00a0 el \u00a0recurso, \u00a0pues \u00a0anuncia, \u00a0indiscriminadamente, \u00a0la \u00a0violaci\u00f3n \u00a0directa \u00a0e \u00a0indirecta \u00a0de la ley sustancial, concretando, \u00a0 \u00a0 \u00a0esta \u00a0 \u00a0 \u00a0\u00faltima, \u00a0en \u00a0un error de hecho por falso juicio \u00a0de identidad que tampoco demuestra. \u00a0\u00a0<\/p>\n<p>Aun cuando advierte que en relaci\u00f3n con los \u00a0testimonios \u00a0referenciados \u00a0en \u00a0el \u00a0cargo, \u00a0el \u00a0Tribunal \u00a0s\u00ed \u00a0los \u00a0valor\u00f3 pero \u00a0parcel\u00f3 \u00a0su \u00a0contenido, \u00a0aspecto \u00a0que \u00a0implicar\u00eda \u00a0distorsi\u00f3n \u00a0del \u00a0contenido \u00a0f\u00e1ctico \u00a0 \u00a0 \u00a0por \u00a0 \u00a0 cercenamiento, \u00a0 \u00a0 omite \u00a0 \u00a0 demostrarlo \u00a0 \u00a0 y, \u00a0nuevamente, \u00a0se \u00a0dedica \u00a0a \u00a0exponer su \u00a0opini\u00f3n \u00a0personal \u00a0en cuanto a la manera como se debieron analizar, en el marco \u00a0de \u00a0un \u00a0discurso extenso y engorroso que no concreta la manera c\u00f3mo el juzgador \u00a0recort\u00f3 la expresi\u00f3n f\u00e1ctica de los medios de convicci\u00f3n. \u00a0\u00a0<\/p>\n<p>Un \u00a0defecto \u00a0de esa naturaleza se demuestra \u00a0mediante \u00a0la \u00a0comparaci\u00f3n entre aquello que dice el elemento con lo manifestado \u00a0al \u00a0respecto \u00a0por \u00a0el \u00a0fallador, \u00a0en \u00a0orden \u00a0a \u00a0comprobar que puso a decir a las \u00a0pruebas \u00a0cuestionadas \u00a0algo \u00a0que objetivamente ellas no expresan y su incidencia \u00a0determinante en la decisi\u00f3n confutada. \u00a0\u00a0<\/p>\n<p>No se trata, como lo entiende el funcionario \u00a0impugnante, \u00a0de \u00a0resumir \u00a0el \u00a0contenido \u00a0de \u00a0los \u00a0testimonios y, con base en ese \u00a0referente, \u00a0presentar \u00a0una \u00a0alternativa \u00a0de \u00a0valoraci\u00f3n \u00a0distinta, encaminada a \u00a0refrendar \u00a0aquellos \u00a0t\u00e9rminos \u00a0de \u00a0la acusaci\u00f3n formulados contra la implicada \u00a0por \u00a0el \u00a0delito \u00a0de lavado de activos que no tuvieron acogida en las instancias. \u00a0\u00a0<\/p>\n<p>Lo \u00a0anterior es as\u00ed porque, seg\u00fan afirma, \u00a0los \u00a0reclamos \u00a0que \u00a0hace \u00a0recaer en las declaraciones de V\u00edctor Arturo Bastidas \u00a0Bastidas, \u00a0Carlos \u00a0Alfredo \u00a0Su\u00e1rez, \u00a0Jhon Esteban Ortega Puerta, Sandra Liliana \u00a0Arciniegas, \u00a0Rita \u00a0Leonor \u00a0Estrada \u00a0Salazar \u00a0e \u00a0Iv\u00e1n \u00a0Dar\u00edo \u00a0Moreno \u00a0Chamorro, \u00a0analizados \u00a0desde \u00a0su \u00a0particular \u00a0criterio, \u00a0conducen \u00a0a \u00a0evidenciar \u00a0el \u00a0papel \u00a0protag\u00f3nico \u00a0 \u00a0desempe\u00f1ado \u00a0 \u00a0por \u00a0 la \u00a0 acusada, \u00a0 frente \u00a0 al \u00a0 injusto \u00a0 en \u00a0comento. \u00a0\u00a0<\/p>\n<p>Entonces, \u00a0no \u00a0hay duda que el discurso del \u00a0recurrente \u00a0tiene \u00a0como verdadero prop\u00f3sito disentir de la estimaci\u00f3n judicial \u00a0y, \u00a0por \u00a0ello, \u00a0exalta, \u00a0de \u00a0cada \u00a0relato, \u00a0el \u00a0papel \u00a0desempe\u00f1ado \u00a0 \u00a0por \u00a0 \u00a0Yady \u00a0 Marilyn \u00a0 en \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0empresa \u00a0 \u00a0 captadora, \u00a0 \u00a0 especialmente, \u00a0en \u00a0las sedes de Ipiales y T\u00faquerres, \u00a0administradas por su hermana Sandra Chamorro y su grupo familiar. \u00a0\u00a0<\/p>\n<p>Bastante \u00a0se \u00a0ha \u00a0insistido \u00a0que \u00a0cualquier \u00a0reproche \u00a0dirigido \u00a0a \u00a0cuestionar \u00a0la \u00a0valoraci\u00f3n \u00a0judicial de los elementos de \u00a0juicio, \u00a0como ocurre en este caso, resulta por completo extra\u00f1o a la casaci\u00f3n, \u00a0dada \u00a0 la \u00a0 libertad \u00a0que \u00a0tiene \u00a0el \u00a0sentenciador \u00a0para \u00a0apreciar \u00a0el \u00a0conjunto \u00a0probatorio, \u00a0 \u00a0limitado \u00a0 \u00a0\u00fanicamente \u00a0 por \u00a0 los \u00a0 postulados \u00a0 de \u00a0 la \u00a0 sana \u00a0cr\u00edtica. \u00a0\u00a0<\/p>\n<p>S\u00f3lo \u00a0 si \u00a0se \u00a0constata \u00a0que \u00a0arrib\u00f3 \u00a0a \u00a0conclusiones \u00a0il\u00f3gicas \u00a0o irrazonables, por desconocimiento de las reglas de la \u00a0l\u00f3gica, \u00a0la ciencia y\/o la experiencia, es procedente el ataque por la v\u00eda del \u00a0error \u00a0de \u00a0hecho \u00a0por \u00a0falso \u00a0raciocinio, \u00a0caso \u00a0en \u00a0el \u00a0cual el impugnante debe \u00a0demostrar \u00a0el postulado cient\u00edfico, el principio de la l\u00f3gica, o la m\u00e1xima de \u00a0la \u00a0experiencia \u00a0que \u00a0fue \u00a0desconocida por el juez e indicar la trascendencia de \u00a0ese \u00a0 error, \u00a0 de \u00a0 modo \u00a0 que \u00a0 sin \u00a0\u00e9l \u00a0otro \u00a0hubiera \u00a0sido \u00a0el \u00a0sentido \u00a0del \u00a0fallo. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0 debe \u00a0 se\u00f1alar \u00a0 el \u00a0 aporte \u00a0cient\u00edfico, \u00a0el \u00a0raciocinio l\u00f3gico, o la deducci\u00f3n por experiencia que debi\u00f3 \u00a0aplicarse en el asunto sometido a debate. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a04. \u00a0Importa \u00a0precisar, \u00a0para \u00a0dar claridad a las descontextualizadas \u00a0quejas \u00a0 del \u00a0 demandante, \u00a0 que \u00a0 el \u00a0Tribunal \u00a0dio \u00a0aplicaci\u00f3n \u00a0al \u00a0principio \u00a0in \u00a0 dubio \u00a0pro \u00a0reo \u00a0tras \u00a0advertir \u00a0que \u00a0se \u00a0presentaban \u00a0grandes \u00a0dudas \u00a0acerca de la intervenci\u00f3n de la \u00a0procesada en la conducta de lavado de activos, pues, \u00a0\u00a0<\/p>\n<p>\u2026en \u00a0el \u00a0proceso \u00a0s\u00f3lo \u00a0se \u00a0demostr\u00f3 \u00a0concretamente \u00a0un \u00a0acto \u00a0de \u00a0captaci\u00f3n \u00a0de \u00a0dineros por cuant\u00eda de $114.000.00 \u00a0[enti\u00e9ndase \u00a0 ciento \u00a0 catorce \u00a0millones] \u00a0y \u00a0su \u00a0intervenci\u00f3n \u00a0en \u00a0una \u00a0feria \u00a0promocional \u00a0adelantada \u00a0en \u00a0T\u00faquerres \u00a0por \u00a0DRFE, \u00a0que \u00a0en \u00a0honor a la verdad, \u00a0resulta \u00a0poco \u00a0significativo, \u00a0frente \u00a0a la informaci\u00f3n parcial referida por la \u00a0misma \u00a0Superintendencia \u00a0en \u00a0la \u00a0Resoluci\u00f3n \u00a01778 \u00a0de \u00a02008, \u00a0con base en datos \u00a0suministrados \u00a0por el establecimiento de comercio del se\u00f1or Su\u00e1rez, seg\u00fan los \u00a0cuales, \u00a0entre abril y septiembre de 2008 se realizaron captaciones por valor de \u00a0$411.13 \u00a0millones \u00a0correspondientes a 94024 obligaciones derivadas de captaci\u00f3n \u00a0de \u00a0dineros, \u00a0sin \u00a0tener en cuenta otras acreencias, fuera de que no obra prueba \u00a0que \u00a0 demuestre \u00a0una \u00a0actividad \u00a0permanente \u00a0de \u00a0la \u00a0procesada \u00a0como \u00a0asesora \u00a0o \u00a0franquiciante \u00a0de \u00a0DRFE, \u00a0para \u00a0lo \u00a0cual \u00a0se \u00a0debe \u00a0tener en cuenta la prueba de \u00a0descargos \u00a0proveniente de los propios funcionarios de la Fiscal\u00eda General de la \u00a0Naci\u00f3n \u00a0que \u00a0laboraban en las dependencias en que trabajaba la se\u00f1ora Chamorro \u00a0en \u00a0el sentido de que la acusada no se desempe\u00f1aba como asesora de DRFE, ni era \u00a0cierto \u00a0que se formaran filas de gente ante su despacho para recibir dineros con \u00a0destino \u00a0a \u00a0esa \u00a0empresa. A lo anterior se agrega que la Fiscal\u00eda, por falta de \u00a0descubrimiento \u00a0probatorio, \u00a0no alleg\u00f3 a (sic) prueba documental y t\u00e9cnica que \u00a0demostrara \u00a0una \u00a0participaci\u00f3n \u00a0esencial \u00a0de la acusada en los actos realizados \u00a0por \u00a0DRFE, \u00a0y \u00a0por \u00a0lo \u00a0cual \u00a0s\u00f3lo \u00a0se \u00a0pudo demostrar su responsabilidad en la \u00a0violaci\u00f3n \u00a0al \u00a0art\u00edculo 316 del C.P., lo que resulta diverso a las inflexiones \u00a0verbales \u00a0adquirir, \u00a0resguardar, invertir, transportar, transformar, custodiar o \u00a0administrar \u00a0bienes \u00a0que \u00a0tenga \u00a0origen\u00a0 mediato o inmediato en los delitos \u00a0contra \u00a0el \u00a0sistema financiero o haberle dado a esos mismos bienes apariencia de \u00a0legalidad \u00a0o \u00a0haberlos legalizado, ocultado o encubierto para encubrir su origen \u00a0il\u00edcito, \u00a0ya \u00a0que \u00a0se \u00a0entiende \u00a0que \u00a0esa \u00a0era \u00a0precisamente \u00a0la \u00a0actividad que \u00a0adelantaba \u00a0Carlos \u00a0Alfredo \u00a0Su\u00e1rez, luego de que recibiera las sumas a trav\u00e9s \u00a0de \u00a0 los \u00a0 m\u00faltiples \u00a0 asesores \u00a0 franquiciantes \u00a0 de \u00a0 su \u00a0empresa13. \u00a0\u00a0<\/p>\n<p>El \u00a0 \u00a0casacionista, \u00a0 se \u00a0 itera, \u00a0 \u00a0en \u00a0 \u00a0lugar \u00a0 \u00a0de \u00a0 enfrentar \u00a0decididamente \u00a0los \u00a0juicios \u00a0del \u00a0sentenciador, \u00a0simplemente \u00a0aporta un punto de \u00a0vista \u00a0distinto, \u00a0dejando \u00a0de atender a los m\u00ednimos requerimientos de claridad, \u00a0precisi\u00f3n \u00a0y \u00a0coherencia, \u00a0indispensables \u00a0para \u00a0entender \u00a0el \u00a0sentido \u00a0de \u00a0las \u00a0censuras, \u00a0as\u00ed \u00a0como la demostraci\u00f3n de los dislates aducidos y la concreci\u00f3n \u00a0de sus consecuencias. \u00a0\u00a0<\/p>\n<p>Y, \u00a0 como \u00a0 no \u00a0 se \u00a0encuentran \u00a0causales \u00a0ostensibles \u00a0de \u00a0nulidad ni flagrantes violaciones de derechos fundamentales, no \u00a0es \u00a0 procedente \u00a0 admitir \u00a0 la \u00a0 demanda \u00a0 para \u00a0 un \u00a0pronunciamiento \u00a0de \u00a0mayor \u00a0fondo. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta decisi\u00f3n procede el mecanismo \u00a0de \u00a0insistencia, de conformidad con lo establecido en el art\u00edculo 184 de la Ley \u00a0906 de 2004. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0la \u00a0Sala de \u00a0Casaci\u00f3n Penal de la Corte Suprema de Justicia, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>INADMITIR \u00a0 las \u00a0demandas examinadas. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta decisi\u00f3n procede el mecanismo \u00a0de \u00a0insistencia, de conformidad con el art\u00edculo 184, inciso 2\u00ba, del C\u00f3digo de \u00a0Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese y c\u00famplase \u00a0<\/p>\n<p>JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0<\/p>\n<p>FERNANDO \u00a0 \u00a0 \u00a0ALBERTO \u00a0 \u00a0 \u00a0CASTRO \u00a0CABALLERO \u00a0\u00a0<\/p>\n<p>EUGENIO FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>MAR\u00cdA \u00a0 DEL \u00a0ROSARIO \u00a0 \u00a0 \u00a0 \u00a0GONZ\u00c1LEZ \u00a0 \u00a0 \u00a0 MU\u00d1OZ \u00a0\u00a0<\/p>\n<p>GUSTAVO \u00a0ENRIQUE \u00a0MALO \u00a0FERN\u00c1NDEZ \u00a0\u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>PATRICIA SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p>1 \u00a0Folios 4 y 5 del escrito de acusaci\u00f3n y CD r\u00e9cord 18:27 a 20:26. \u00a0\u00a0<\/p>\n<p>2 \u00a0Folios 1 a 11 Ib. \u00a0\u00a0<\/p>\n<p>3 Folio \u00a019 Ib. \u00a0\u00a0<\/p>\n<p>4 Folio \u00a0217 Ib. \u00a0\u00a0<\/p>\n<p>5 \u00a0Folios 222 a 251 Ib. \u00a0\u00a0<\/p>\n<p>6 \u00a0Folios 312 a 340 Ib. \u00a0\u00a0<\/p>\n<p>7 \u00a0Sentencia \u00a0del \u00a017 \u00a0de \u00a0Julio 17 de 2003, Rad. 13128, reiterada en Auto del 6 de \u00a0septiembre \u00a0 \u00a0de \u00a0 \u00a02007, \u00a0 \u00a0en \u00a0 \u00a0el \u00a0 marco \u00a0 del \u00a0 nuevo \u00a0 sistema \u00a0 procesal \u00a0acusatorio.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>8 \u00a0R\u00e9cord 19:28 a 19:46 CD No 2. \u00a0\u00a0<\/p>\n<p>9 \u00a0R\u00e9cord 52:37 a 52:51 Ib. \u00a0\u00a0<\/p>\n<p>10 \u00a0R\u00e9cord 19:10 a 19:18 \u00a0\u00a0<\/p>\n<p>11 \u00a0R\u00e9cord 20:25 a 20:35. \u00a0\u00a0<\/p>\n<p>12 \u00a0Folio 335 Ib. \u00a0\u00a0<\/p>\n<p>13 \u00a0Folios 336 y 337 Cuaderno principal. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0\u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 EYDER PATI\u00d1O CABRERA \u00a0 Magistrado Ponente \u00a0 AP2824-2015 \u00a0 Radicaci\u00f3n N\u00b0. 43258 \u00a0 (Aprobado Acta N\u00b0. 184) \u00a0 Bogot\u00e1, \u00a0D.C., \u00a0veinticinco (25) de mayo de \u00a0dos mil quince (2015). \u00a0\u00a0 MOTIVO DE LA DECISI\u00d3N \u00a0 Decide \u00a0la Sala si es procedente admitir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-30901","post","type-post","status-publish","format-standard","hentry","category-23"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/30901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=30901"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/30901\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=30901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=30901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=30901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}