{"id":29152,"date":"2023-09-13T14:18:58","date_gmt":"2023-09-13T14:18:58","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap5819-201443240\/"},"modified":"2023-09-13T14:18:58","modified_gmt":"2023-09-13T14:18:58","slug":"ap5819-201443240","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/13\/ap5819-201443240\/","title":{"rendered":"AP5819-2014(43240)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>Magistrado ponente \u00a0<\/p>\n<p>AP5819-2014 \u00a0<\/p>\n<p>Radicaci\u00f3n N\u00ba 43240 \u00a0<\/p>\n<p>(Aprobado acta N\u00b0 \u00a0318) \u00a0\u00a0<\/p>\n<p>Bogot\u00e1, \u00a0 D.C., \u00a0 veinticuatro \u00a0 (24) \u00a0de \u00a0septiembre de dos mil catorce (2014). \u00a0\u00a0<\/p>\n<p>I. \u00a0 V \u00a0 I \u00a0 S \u00a0 T \u00a0O \u00a0S \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0La \u00a0Sala \u00a0se \u00a0pronuncia \u00a0sobre \u00a0los \u00a0presupuestos \u00a0de \u00a0l\u00f3gica \u00a0y \u00a0debida \u00a0fundamentaci\u00f3n de la demanda de casaci\u00f3n \u00a0presentada \u00a0por \u00a0el \u00a0defensor de Luisa Fernanda Giraldo \u00a0Alape contra el fallo del 27 de noviembre de 2013, por \u00a0medio \u00a0del \u00a0cual \u00a0el \u00a0Tribunal \u00a0Superior \u00a0de Medell\u00edn confirm\u00f3 la decisi\u00f3n de \u00a0primera \u00a0instancia que la conden\u00f3 por los delitos de hurto agravado continuado, \u00a0falsedad \u00a0en \u00a0documento \u00a0privado \u00a0y \u00a0destrucci\u00f3n \u00a0supresi\u00f3n \u00a0y ocultamiento de \u00a0documento p\u00fablico. \u00a0\u00a0<\/p>\n<p>II. H E C H O S \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>El \u00a021 \u00a0de enero de 2009 el se\u00f1or Francisco \u00a0Javier \u00a0Zuluaga \u00a0G\u00f3mez, \u00a0representante \u00a0legal \u00a0de la firma Arrendamientos Nuevo \u00a0Milenio, \u00a0S.A., \u00a0con \u00a0sede \u00a0en Envigado (Ant.), denunci\u00f3 que con ocasi\u00f3n de la \u00a0auditor\u00eda \u00a0interna \u00a0realizada \u00a0en \u00a0dicha empresa el 15 de diciembre de 2008 por \u00a0John \u00a0de \u00a0Jes\u00fas \u00a0Agudelo \u00a0Berm\u00fadez, \u00a0se \u00a0detectaron inconsistencias de diverso \u00a0orden \u00a0en \u00a0la \u00a0gesti\u00f3n \u00a0realizada \u00a0por \u00a0Luisa Fernanda \u00a0Giraldo \u00a0Alape, \u00a0encargada \u00a0de \u00a0la \u00a0Secretar\u00eda \u00a0de la \u00a0agencia, as\u00ed como de la facturaci\u00f3n y recibos de caja. \u00a0\u00a0<\/p>\n<p>Luego \u00a0de \u00a0incurrir \u00a0en \u00a0repetidas \u00a0evasivas \u00a0frente \u00a0a \u00a0los \u00a0requerimientos \u00a0para \u00a0aclarar \u00a0las inconsistencias detectadas la \u00a0secretaria renunci\u00f3, aduciendo que estaba siendo presionada. \u00a0\u00a0<\/p>\n<p>La \u00a0auditor\u00eda \u00a0encontr\u00f3 \u00a0que \u00a0Giraldo \u00a0Alape \u00a0recibi\u00f3 \u00a0y se apropi\u00f3 de \u00a0dinero \u00a0en \u00a0efectivo, \u00a0realiz\u00f3 \u00a0cruces \u00a0de \u00a0cartera \u00a0del \u00a0dinero \u00a0recibi\u00f3 y no \u00a0consignado \u00a0sin \u00a0el \u00a0debido \u00a0soporte, omiti\u00f3 la facturaci\u00f3n del dinero pagado, \u00a0utiliz\u00f3 \u00a0 indebidamente \u00a0 los \u00a0 inmuebles \u00a0 de \u00a0propietarios \u00a0que \u00a0no \u00a0cobraban \u00a0mensualmente \u00a0el \u00a0arriendo, alter\u00f3 los soportes de los recibos elaborados a los \u00a0inquilinos, \u00a0adulter\u00f3 \u00a0los \u00a0recibos de caja, se apropi\u00f3 de cobros jur\u00eddicos y \u00a0dio \u00a0 de \u00a0 baja \u00a0 los \u00a0arrendamientos \u00a0adeudados \u00a0por \u00a0sus \u00a0propios \u00a0familiares. \u00a0\u00a0<\/p>\n<p>El \u00a0valor \u00a0de \u00a0lo \u00a0apropiado fue estimado en \u00a0$200.000.000. \u00a0\u00a0<\/p>\n<p>III. ANTECEDENTES PROCESALES \u00a0<\/p>\n<p>1. \u00a0El \u00a018 \u00a0de \u00a0febrero de 2011, el Juez 3\u00ba \u00a0Penal \u00a0Municipal \u00a0con funci\u00f3n de control de garant\u00edas de Envigado, a solicitud \u00a0de \u00a0la \u00a0Fiscal\u00eda \u00a0245 \u00a0Seccional, \u00a0legaliz\u00f3 \u00a0la \u00a0imputaci\u00f3n \u00a0formulada contra \u00a0Luisa \u00a0Fernanda Giraldo Alape \u00a0por \u00a0los delitos de hurto agravado continuado (art\u00edculos 239, inciso 1\u00ba, 241-2 \u00a0y \u00a031, \u00a0par\u00e1grafo, \u00a0de \u00a0C\u00f3digo \u00a0Penal) \u00a0en \u00a0concurso con falsedad en documento \u00a0privado \u00a0y \u00a0destrucci\u00f3n, \u00a0supresi\u00f3n u ocultamiento de documento privado (arts. \u00a0289 y 293 del mismo estatuto), cargos que la imputada no acept\u00f3. \u00a0\u00a0<\/p>\n<p>2. El escrito de acusaci\u00f3n, por los delitos \u00a0antes \u00a0rese\u00f1ados, \u00a0fue \u00a0radicado \u00a0el \u00a017 \u00a0de \u00a0marzo de 2011. La audiencia de su \u00a0formulaci\u00f3n \u00a0tuvo \u00a0lugar \u00a0ante \u00a0el \u00a0Juez \u00danico Penal del Circuito de Envigado, \u00a0quien \u00a0en \u00a0sesiones del 4 de mayo y 24 de junio reconoci\u00f3 a la representante de \u00a0la \u00a0v\u00edctima, \u00a0la \u00a0firma \u00a0Arrendamientos \u00a0Nuevo Milenio S.A., y neg\u00f3 la nulidad \u00a0reclamada \u00a0por la defensa. La audiencia preparatoria se celebr\u00f3 el 17 de agosto \u00a0y \u00a04 \u00a0de \u00a0octubre \u00a0de 2011; en ella la procesada se declar\u00f3 inocente, al tiempo \u00a0que \u00a0la \u00a0fiscal\u00eda \u00a0y \u00a0la defensa estipularon la identidad de aquella. El juicio \u00a0oral \u00a0tuvo lugar el 19 de julio y 14 de noviembre de 2012, y 4 de abril de 2013. \u00a0En \u00a0esta \u00a0\u00faltima \u00a0fecha \u00a0el \u00a0juez \u00a0anunci\u00f3 el sentido condenatorio del fallo y \u00a0corri\u00f3 el traslado del art\u00edculo 447 de la Ley 906 de 2004. \u00a0\u00a0<\/p>\n<p>3. \u00a0En providencia del 6 de mayo de 2013, el \u00a0juzgado \u00a0 \u00a0conden\u00f3 \u00a0 \u00a0a \u00a0 Luisa \u00a0 Fernanda \u00a0 Giraldo \u00a0Alape \u00a0a la pena principal de 80 meses de prisi\u00f3n y a \u00a0la \u00a0accesoria \u00a0de \u00a0inhabilitaci\u00f3n \u00a0para \u00a0el \u00a0ejercicio \u00a0de derechos y funciones \u00a0p\u00fablicas \u00a0por \u00a0un \u00a0t\u00e9rmino \u00a0semejante \u00a0al de la pena privativa de la libertad, \u00a0como \u00a0 autora \u00a0 de \u00a0las \u00a0conductas \u00a0punibles \u00a0por \u00a0las \u00a0que \u00a0fue \u00a0acusada.\u00a0 \u00a0\u00a0<\/p>\n<p>La \u00a0defensa \u00a0de \u00a0la \u00a0procesada \u00a0apel\u00f3 \u00a0la \u00a0decisi\u00f3n \u00a0condenatoria, \u00a0la \u00a0cual \u00a0fue \u00a0confirmada \u00a0por el Tribunal Superior de \u00a0Antioquia \u00a0en \u00a0sentencia \u00a0del \u00a027 \u00a0de \u00a0noviembre de 2013, al tiempo que neg\u00f3 la \u00a0nulidad pedida por el citado sujeto procesal. \u00a0\u00a0<\/p>\n<p>4. \u00a0En \u00a0contra \u00a0de \u00a0lo \u00a0dispuesto \u00a0por \u00a0el \u00a0ad \u00a0quem, el apoderado de la \u00a0sentenciada \u00a0interpuso oportunamente el recurso extraordinario de casaci\u00f3n y lo \u00a0sustent\u00f3 mediante el correspondiente libelo. \u00a0\u00a0<\/p>\n<p>IV. \u00a0L \u00a0A\u00a0\u00a0\u00a0 \u00a0D \u00a0E \u00a0M \u00a0A \u00a0N D \u00a0A \u00a0\u00a0<\/p>\n<p>Al \u00a0amparo \u00a0de la causal de casaci\u00f3n de que \u00a0trata \u00a0el \u00a0art\u00edculo \u00a0181, \u00a0numeral \u00a02\u00ba, \u00a0de \u00a0la Ley 906 de 2004, el impugnante \u00a0propone \u00a0un \u00a0cargo \u00a0de \u00a0nulidad, \u00a0a \u00a0trav\u00e9s \u00a0del cual pregona la afectaci\u00f3n al \u00a0debido proceso por violaci\u00f3n al derecho a la defensa t\u00e9cnica. \u00a0\u00a0<\/p>\n<p>En medio de la reiteraci\u00f3n de los argumentos \u00a0de \u00a0la \u00a0apelaci\u00f3n contra el fallo del juzgado, alega que su asistida cont\u00f3 con \u00a0el \u00a0 acompa\u00f1amiento \u00a0 de \u00a0 un \u00a0defensor, \u00a0pero \u00a0dicho \u00a0acompa\u00f1amiento \u00a0no \u00a0fue \u00a0cualificado, \u00a0como \u00a0lo \u00a0exige \u00a0la \u00a0jurisprudencia de la Corte en los apartes que \u00a0trascribe. \u00a0\u00a0<\/p>\n<p>As\u00ed, \u00a0 \u00a0asegura \u00a0 que \u00a0 \u201cno \u00a0se \u00a0puede \u00a0considerar \u00a0acompa\u00f1amiento \u00a0cualificado\u201d \u00a0que \u00a0la \u00a0defensa anterior no hubiera cuestionado a los expertos \u00a0en \u00a0contabilidad, software y grafolog\u00eda de la fiscal\u00eda; que hubiera tratado de \u00a0rebatirlos \u00a0con \u00a0el \u00a0testimonio \u00a0de legos en la materia y no con otros expertos; \u00a0que \u00a0 los \u00a0 contrainterrogatorios \u00a0 hubieran \u00a0sido \u00a0deficientes, \u00a0al \u00a0punto \u00a0que \u00a0terminaran \u00a0por \u00a0apoyar \u00a0la \u00a0tesis del acusador; que el juez le hubiera dicho al \u00a0defensor \u00a0que \u00a0no aplicaba las reglas del contrainterrogatorio y que el defensor \u00a0no \u00a0 atacara \u00a0 \u201clos \u00a0 extremos \u00a0relevantes \u00a0de \u00a0la \u00a0acusaci\u00f3n\u201d. \u00a0\u00a0<\/p>\n<p>Considera, como as\u00ed lo argument\u00f3 al apelar \u00a0el \u00a0fallo \u00a0del \u00a0a quo, que no \u00a0era \u00a0v\u00e1lido \u00a0que \u00a0el \u00a0anterior \u00a0defensor \u00a0se \u00a0hubiera \u00a0centrado en reclamar una \u00a0nulidad con fundamento en la err\u00f3nea calificaci\u00f3n de la conducta. \u00a0\u00a0<\/p>\n<p>Manifiesta \u00a0su discrepancia con el argumento \u00a0del \u00a0Tribunal, \u00a0seg\u00fan \u00a0el \u00a0cual \u00a0la \u00a0contundencia \u00a0de \u00a0la \u00a0prueba \u00a0de cargo era \u00a0innegable, \u00a0pues \u00a0dicha \u00a0prueba fue la practicada por solicitud de la fiscal\u00eda; \u00a0alega \u00a0que \u00a0\u201cla asesor\u00eda t\u00e9cnica obliga a manejar \u00a0el \u00a0asunto \u00a0de forma profesional buscando el mejor de los mundos para el cliente \u00a0ca\u00eddo \u00a0en desgracia\u201d. Agrega que fue por lo anterior \u00a0que \u00a0en \u00a0recurso \u00a0de \u00a0apelaci\u00f3n \u00a0expres\u00f3 \u00a0que \u00a0si \u00a0en \u00a0realidad \u00a0la prueba era \u00a0contundente \u00a0 el \u00a0 defensor \u00a0 ha \u00a0 debido \u00a0explorar \u00a0salidas \u00a0alternas \u00a0para \u00a0la \u00a0terminaci\u00f3n del proceso. \u00a0\u00a0<\/p>\n<p>Pide, \u00a0al \u00a0igual \u00a0que \u00a0lo hizo en el aludido \u00a0recurso \u00a0de apelaci\u00f3n, que se anule lo actuado \u201cmuy \u00a0posiblemente \u00a0a \u00a0partir \u00a0de \u00a0la \u00a0audiencia \u00a0de \u00a0imputaci\u00f3n \u00a0o \u00a0m\u00ednimo desde la \u00a0audiencia preparatoria\u201d. \u00a0\u00a0<\/p>\n<p>V. CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>La \u00a0Corporaci\u00f3n anticipa su decisi\u00f3n en el \u00a0sentido \u00a0 de \u00a0 inadmitir \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n, \u00a0toda vez que evidentemente incumple los presupuestos de \u00a0debida \u00a0fundamentaci\u00f3n \u00a0que deben guiar su sustentaci\u00f3n.\u00a0 Las razones son \u00a0las siguientes: \u00a0\u00a0<\/p>\n<p>1. \u00a0 La \u00a0 demanda \u00a0 de \u00a0casaci\u00f3n \u00a0resulta \u00a0manifiestamente \u00a0inconducente \u00a0para \u00a0demostrar \u00a0la \u00a0ilegalidad \u00a0del \u00a0fallo, pues \u00a0analizada \u00a0con \u00a0atenci\u00f3n \u00a0y \u00a0comparado \u00a0su \u00a0contenido \u00a0con \u00a0el \u00a0del \u00a0recurso de \u00a0apelaci\u00f3n \u00a0dirigido \u00a0contra \u00a0la \u00a0decisi\u00f3n \u00a0del \u00a0juzgado, \u00a0surge n\u00edtido que en \u00a0realidad \u00a0aquella \u00a0no \u00a0pasa de insistir en id\u00e9nticos argumentos a los ofrecidos \u00a0en \u00a0la instancia, haciendo caso omiso a los ponderados y acertados razonamientos \u00a0mediante \u00a0 los \u00a0 cuales \u00a0 del \u00a0 ad \u00a0quem \u00a0dio \u00a0respuesta a las inquietudes defensivas.\u00a0 Tan evidente es \u00a0lo \u00a0anterior que el demandante sustenta la mayor parte del libelo a partir de la \u00a0trascripci\u00f3n literal del aludido recurso de apelaci\u00f3n.\u00a0 \u00a0\u00a0<\/p>\n<p>Ser\u00eda \u00a0suficiente lo anterior para concluir \u00a0en \u00a0la \u00a0necesaria \u00a0inadmisi\u00f3n de la demanda, pues esta no trae nada distinto al \u00a0argumento \u00a0de \u00a0instancia, \u00a0el \u00a0cual \u00a0fue \u00a0desestimado \u00a0por \u00a0el \u00a0Tribunal \u00a0en una \u00a0decisi\u00f3n \u00a0que, integrada con la del a quo, \u00a0conforman \u00a0una \u00a0unidad que llega a esta sede amparada en la doble \u00a0presunci\u00f3n de acierto y legalidad. \u00a0\u00a0<\/p>\n<p>2. No obstante lo anterior, no sobra recordar \u00a0que \u00a0cuando en esta sede se propone como fundamento de una posible violaci\u00f3n al \u00a0derecho \u00a0a la defensa, por deficiencias en la gesti\u00f3n de la defensa letrada, la \u00a0Sala \u00a0tiene \u00a0dicho \u00a0que no es de recibo pretender demostrar el vicio a partir de \u00a0la \u00a0sola \u00a0discrepancia \u00a0con \u00a0la \u00a0gesti\u00f3n \u00a0defensiva \u00a0desplegada por el anterior \u00a0apoderado, \u00a0tampoco \u00a0con \u00a0la \u00a0propuesta \u00a0de lo que el casacionista considera una \u00a0mejor \u00a0actuaci\u00f3n, \u00a0menos \u00a0a\u00fan \u00a0con \u00a0la \u00a0enunciaci\u00f3n de un listado de posibles \u00a0actuaciones \u00a0que, \u00a0de \u00a0manera incierta o apenas hipot\u00e9tica, podr\u00edan conducir a \u00a0un mejor resultado (CSJ SP, 3 de julio de 2013, Rad. 40568). \u00a0\u00a0<\/p>\n<p>Por \u00a0el \u00a0contrario, \u00a0al \u00a0censor \u00a0le \u00a0compete \u00a0demostrar \u00a0de \u00a0manera \u00a0concreta, \u00a0y \u00a0no \u00a0a \u00a0partir \u00a0de \u00a0un \u00a0juicio \u00a0ex \u00a0post frente al resultado ya conocido o \u00a0con \u00a0la \u00a0sola \u00a0expectativa \u00a0de \u00a0un resultado distinto, que la deficiente defensa \u00a0t\u00e9cnica \u00a0configur\u00f3 \u00a0una \u00a0irregularidad \u00a0de \u00a0car\u00e1cter \u00a0sustancial, \u00a0con \u00a0clara \u00a0incidencia en una lesi\u00f3n irreparable al derecho de defensa. \u00a0\u00a0<\/p>\n<p>En \u00a0el caso presente, la cr\u00edtica casacional \u00a0se \u00a0qued\u00f3 \u00a0en \u00a0el \u00a0cuestionamiento \u00a0a \u00a0la \u00a0gesti\u00f3n \u00a0profesional \u00a0del \u00a0anterior \u00a0defensor, \u00a0pues el impugnante no precis\u00f3 qu\u00e9 era aquello que el abogado que lo \u00a0antecedi\u00f3 \u00a0en \u00a0el cargo hubiera podido demostrar a trav\u00e9s de otros peritajes y \u00a0que \u00a0necesariamente \u00a0hubiera \u00a0incidido \u00a0en \u00a0el resultado del proceso. Menos a\u00fan \u00a0especific\u00f3 \u00a0qu\u00e9 \u00a0relevancia \u00a0pudo \u00a0tener \u00a0en \u00a0el \u00a0resultado \u00a0el \u00a0supuestamente \u00a0deficiente \u00a0contrainterrogatorio, \u00a0o \u00a0bien \u00a0qu\u00e9 \u00a0fue \u00a0aquello \u00a0por \u00a0lo \u00a0que \u00a0el \u00a0apoderado \u00a0de \u00a0entonces \u00a0debi\u00f3 indagar y c\u00f3mo dicho omisi\u00f3n fue decisiva para \u00a0el resultado perjudicial a los intereses de su asistida. \u00a0\u00a0<\/p>\n<p>Por \u00a0otra \u00a0parte, \u00a0f\u00e1cil \u00a0resulta \u00a0en \u00a0este \u00a0momento, \u00a0cuando \u00a0el \u00a0proceso \u00a0ha \u00a0concluido \u00a0y \u00a0se \u00a0conocen \u00a0los \u00a0razonamientos \u00a0jur\u00eddicos \u00a0y \u00a0las apreciaciones probatorias del juzgador, criticar las posturas \u00a0defensivas \u00a0del \u00a0colega, \u00a0como \u00a0el \u00a0reclamo \u00a0de una nulidad con fundamento a una \u00a0indebida \u00a0calificaci\u00f3n \u00a0de \u00a0la \u00a0conducta, \u00a0o \u00a0bien \u00a0la \u00a0no \u00a0consideraci\u00f3n \u00a0del \u00a0acogimiento \u00a0al \u00a0mecanismo de terminaci\u00f3n anticipada o la pr\u00e1ctica de un mejor \u00a0interrogatorio. \u00a0\u00a0<\/p>\n<p>As\u00ed las cosas, como lo plasm\u00f3 el Tribunal y \u00a0lo \u00a0evidencia \u00a0la \u00a0actuaci\u00f3n \u00a0procesal, \u00a0sin \u00a0que \u00a0el \u00a0libelista \u00a0demostrara lo \u00a0contrario, \u00a0el resultado de la actuaci\u00f3n fue m\u00e1s la consecuencia natural de la \u00a0contundencia \u00a0de \u00a0la prueba que de la manifiesta negligencia o incompetencia del \u00a0apoderado judicial.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>D\u00edgase \u00a0que en el ejercicio de una adecuada \u00a0gesti\u00f3n \u00a0defensiva \u00a0no \u00a0es \u00a0posible \u00a0asegurar \u00a0de \u00a0antemano que una determinada \u00a0estrategia \u00a0ser\u00e1 \u00a0m\u00e1s \u00a0exitosa que otra; incluso, una cierta postura defensiva \u00a0puede \u00a0ser \u00a0excluyente \u00a0respecto \u00a0de otra, siendo ambas jur\u00eddicas y razonables. \u00a0Este \u00a0\u00faltimo \u00a0es \u00a0uno \u00a0de \u00a0los defectos en que incurre el argumento casacional, \u00a0pues \u00a0por \u00a0una \u00a0parte \u00a0asegura que la presentaci\u00f3n por la defensa de peritos en \u00a0software \u00a0y \u00a0contabilidad, \u00a0o \u00a0la realizaci\u00f3n de un mejor contrainterrogatorio, \u00a0hubiera \u00a0conducido \u00a0a \u00a0un \u00a0mejor \u00a0resultado, \u00a0pero \u00a0por \u00a0la otra alega que mejor \u00a0hubiera \u00a0 sido \u00a0 que \u00a0la \u00a0procesada \u00a0se \u00a0acogiera \u00a0a \u00a0la \u00a0sentencia \u00a0anticipada. \u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0 las \u00a0 cosas, \u00a0el \u00a0razonamiento \u00a0del \u00a0demandante \u00a0es \u00a0claramente \u00a0contradictorio \u00a0pues, \u00a0al \u00a0tiempo \u00a0que \u00a0le achaca al \u00a0entonces \u00a0defensor \u00a0que \u00a0no \u00a0hubiera \u00a0realizado \u00a0una mejor pr\u00e1ctica probatoria, \u00a0tambi\u00e9n \u00a0le \u00a0critica \u00a0que \u00a0no \u00a0hubiera \u00a0renunciado \u00a0a \u00a0ella \u00a0y \u00a0optado \u00a0por \u00a0el \u00a0reconocimiento de la responsabilidad de su asistida. \u00a0\u00a0<\/p>\n<p>En conclusi\u00f3n, reitera la Corte, el alegato \u00a0casacional \u00a0se \u00a0contrae \u00a0a \u00a0discrepar \u00a0de \u00a0la gesti\u00f3n defensiva ejercida por el \u00a0defensor \u00a0anterior, \u00a0sin \u00a0demostrar \u00a0que una supuesta defensa letrada deficiente \u00a0hubiera \u00a0generado \u00a0un \u00a0claro \u00a0e \u00a0irremediable perjuicio al derecho a la defensa. \u00a0\u00a0<\/p>\n<p>3. As\u00ed las cosas, por no cumplir la demanda \u00a0los \u00a0 \u00a0 presupuestos \u00a0 \u00a0de \u00a0 \u00a0debida \u00a0 \u00a0fundamentaci\u00f3n \u00a0 \u00a0ser\u00e1 \u00a0 \u00a0inadmitida a esta sede extraordinaria, sin \u00a0que, \u00a0por \u00a0otra parte, del estudio de las diligencias la Sala de Casaci\u00f3n Penal \u00a0encuentre \u00a0motivo \u00a0que amerite superar sus defectos para asegurar, de oficio, el \u00a0cumplimiento \u00a0 \u00a0de \u00a0 \u00a0las \u00a0 \u00a0garant\u00edas \u00a0 \u00a0fundamentales \u00a0 o \u00a0 los \u00a0 fines \u00a0 del \u00a0recurso. \u00a0\u00a0<\/p>\n<p>En \u00a0contra de esta determinaci\u00f3n procede el \u00a0mecanismo \u00a0de \u00a0insistencia, \u00a0en \u00a0los \u00a0t\u00e9rminos en que la jurisprudencia de esta \u00a0Colegiatura \u00a0 lo \u00a0 ha \u00a0 decantado \u00a0(CSJ \u00a0SP, \u00a012 \u00a0de \u00a0diciembre \u00a0de \u00a02005, \u00a0Rad. \u00a025322). \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de lo expuesto, la CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0SALA \u00a0DE \u00a0CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>VI. R E S U E L V E \u00a0<\/p>\n<p>INADMITIR \u00a0la \u00a0demanda \u00a0 \u00a0de \u00a0 casaci\u00f3n \u00a0 presentada \u00a0 por \u00a0 el \u00a0 defensor \u00a0 de \u00a0 Luisa \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Fernanda \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Giraldo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Alape. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta decisi\u00f3n procede el mecanismo \u00a0de insistencia. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0 notif\u00edquese, \u00a0 c\u00famplase \u00a0y \u00a0devu\u00e9lvase al Tribunal de origen \u00a0\u00a0<\/p>\n<p>FERNANDO ALBERTO CASTRO CABALLERO \u00a0<\/p>\n<p>Presidente \u00a0<\/p>\n<p>JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0<\/p>\n<p>EUGENIO FERN\u00c1NDEZ CARLIER \u00a0<\/p>\n<p>MAR\u00cdA \u00a0 \u00a0DEL \u00a0 \u00a0ROSARIO \u00a0 \u00a0GONZ\u00c1LEZ \u00a0MU\u00d1OZ \u00a0\u00a0<\/p>\n<p>GUSTAVO ENRIQUE MALO FERN\u00c1NDEZ \u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>PATRICIA SALAZAR CU\u00c9LLAR \u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 JOS\u00c9 LUIS BARCEL\u00d3 CAMACHO \u00a0 Magistrado ponente \u00a0 AP5819-2014 \u00a0 Radicaci\u00f3n N\u00ba 43240 \u00a0 (Aprobado acta N\u00b0 \u00a0318) \u00a0\u00a0 Bogot\u00e1, \u00a0 D.C., \u00a0 veinticuatro \u00a0 (24) \u00a0de \u00a0septiembre de dos mil catorce (2014). \u00a0\u00a0 I. \u00a0 V \u00a0 I \u00a0 S \u00a0 T [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-29152","post","type-post","status-publish","format-standard","hentry","category-22"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/29152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=29152"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/29152\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=29152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=29152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=29152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}