{"id":27355,"date":"2023-09-12T19:54:24","date_gmt":"2023-09-12T19:54:24","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/4204711-12-13\/"},"modified":"2023-09-12T19:54:24","modified_gmt":"2023-09-12T19:54:24","slug":"4204711-12-13","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/4204711-12-13\/","title":{"rendered":"42047(11-12-13)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0<\/p>\n<p>Aprobado acta N\u00ba 419 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D.C., \u00a0once \u00a0de diciembre de dos mil \u00a0trece. \u00a0\u00a0<\/p>\n<p>V \u00a0 I \u00a0 S \u00a0 T \u00a0 O \u00a0 S \u00a0\u00a0<\/p>\n<p>La \u00a0sala \u00a0se \u00a0ocupa \u00a0de \u00a0la admisibilidad del \u00a0recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n \u00a0formulado \u00a0por \u00a0el \u00a0defensor \u00a0del se\u00f1or \u00a0H\u00c9CTOR \u00a0GUMERCINDO \u00a0CEBALLOS ROSERO contra la sentencia por medio de la cual el \u00a0Tribunal \u00a0Superior \u00a0del \u00a0Distrito \u00a0Judicial \u00a0de \u00a0Pasto \u00a0confirm\u00f3 \u00a0el \u00a0fallo \u00a0de \u00a0car\u00e1cter \u00a0condenatorio \u00a0proferido \u00a0por \u00a0el \u00a0Juzgado \u00a06\u00ba Penal del Circuito con \u00a0Funciones \u00a0de \u00a0Conocimiento \u00a0de \u00a0la \u00a0misma \u00a0ciudad, \u00a0al hallarlo responsable del \u00a0punible de lesiones personales culposas. \u00a0\u00a0<\/p>\n<p>H \u00a0 E \u00a0 C \u00a0 H \u00a0 O \u00a0 S\u00a0\u00a0 \u00a0 Y\u00a0 \u00a0ANTECEDENTES \u00a0\u00a0<\/p>\n<p>El episodio f\u00e1ctico as\u00ed fue relatado por el \u00a0Tribunal: \u00a0\u00a0<\/p>\n<p>\u201cSe tiene probado que el d\u00eda 27 de julio \u00a0de \u00a02007 \u00a0el \u00a0se\u00f1or \u00a0H\u00c9CTOR \u00a0GUMERCINDO \u00a0CEBALLOS \u00a0ROSERO \u00a0llev\u00f3 un veh\u00edculo \u00a0automotor \u00a0suyo \u00a0a \u00a0un \u00a0parqueadero \u00a0ubicado \u00a0en el barrio El potrerillo de esta \u00a0ciudad, \u00a0donde \u00a0requiri\u00f3 \u00a0servicios \u00a0de \u00a0mec\u00e1nica \u00a0ofrecidos por JUAN BAUTISTA \u00a0GUACALES \u00a0PASCUAZA, \u00a0quien previo a culminar un trabajo de refacci\u00f3n al rodante \u00a0y \u00a0prever la realizaci\u00f3n de otro, dio orden a aqu\u00e9l para que lo encendiera, el \u00a0cual \u00a0a \u00a0su \u00a0vez \u00a0ejecut\u00f3 la acci\u00f3n desde el sitio donde se encontraba en pie, \u00a0vale decir sin subirse a la cabina. \u00a0\u00a0<\/p>\n<p>Toda \u00a0vez \u00a0que \u00a0el carro no se encontraba en \u00a0neutro, \u00a0hizo \u00a0entonces \u00a0s\u00fabito \u00a0y \u00a0descontrolado \u00a0desplazamiento arrollando al \u00a0mec\u00e1nico, \u00a0el se\u00f1or GUACALES PASCUAZA, estrell\u00e1ndolo contra unos furgones que \u00a0se \u00a0hallaban \u00a0estacionados \u00a0al frente y caus\u00e1ndole a la postre politraumatismos \u00a0graves \u00a0y diversas lesiones que le afectaron principalmente el rostro, siendo la \u00a0m\u00e1s \u00a0grave aquella que le gener\u00f3 \u201cperturbaci\u00f3n funcional de los \u00f3rganos de \u00a0la visi\u00f3n y audici\u00f3n de car\u00e1cter permanente\u201d.\u201d \u00a0\u00a0<\/p>\n<p>Con base en estos hechos, el d\u00eda 5 de julio \u00a0de \u00a02012 \u00a0la \u00a0Fiscal\u00eda \u00a0le \u00a0imput\u00f3 \u00a0al se\u00f1or CEBALLOS ROSERO la comisi\u00f3n, en \u00a0calidad \u00a0de \u00a0autor, \u00a0del delito de lesiones personales culposas, ante el Juzgado \u00a0Primero \u00a0Penal \u00a0Municipal \u00a0con \u00a0Funciones \u00a0de Control de Garant\u00edas de Pasto, el \u00a0cual \u00a0no \u00a0fue aceptado, y en consecuencia, el escrito de acusaci\u00f3n fue radicado \u00a0el \u00a02 \u00a0de \u00a0octubre siguiente y el 10 de diciembre se realiz\u00f3 la audiencia de su \u00a0formulaci\u00f3n oral. \u00a0\u00a0<\/p>\n<p>La audiencia preparatoria se llev\u00f3 a cabo el \u00a08 \u00a0de \u00a0enero de 2013, y la del juicio oral en sesiones realizadas los d\u00edas 4, 5 \u00a0y \u00a08 \u00a0de \u00a0febrero, \u00a0a \u00a0cuya \u00a0finalizaci\u00f3n \u00a0se \u00a0anunci\u00f3 \u00a0el \u00a0sentido \u00a0del fallo \u00a0condenatorio y la lectura de la sentencia se realiz\u00f3 el\u00a0 \u00a0\u00a0<\/p>\n<p>28 \u00a0del mismo mes, contra la cual la defensa \u00a0interpuso el recurso de apelaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Por \u00a0su \u00a0parte, \u00a0el \u00a0Tribunal \u00a0Superior \u00a0del \u00a0Distrito \u00a0Judicial \u00a0de \u00a0Pasto \u00a0confirm\u00f3 \u00a0el fallo recurrido, mediante sentencia \u00a0calendada \u00a0el 5 de junio del corriente a\u00f1o, contra la que a su vez, la defensa, \u00a0interpuso \u00a0el \u00a0recurso \u00a0extraordinario de casaci\u00f3n, cuya admisibilidad ahora se \u00a0analiza. \u00a0\u00a0<\/p>\n<p>LA SENTENCIA IMPUGNADA \u00a0<\/p>\n<p>El \u00a0 Tribunal, \u00a0al \u00a0considerar \u00a0probada \u00a0la \u00a0violaci\u00f3n \u00a0de \u00a0una \u00a0norma \u00a0de \u00a0cuidado \u00a0por \u00a0parte \u00a0del \u00a0acusado, \u00a0lo encontr\u00f3 \u00a0responsable \u00a0 del \u00a0 delito \u00a0imputado \u00a0\u2013lesiones \u00a0personales \u00a0culposas,\u00a0 art\u00edculos 114 inciso segundo, \u00a0117 \u00a0y \u00a0120 \u00a0del \u00a0C\u00f3digo \u00a0Penal-, y en consecuencia confirm\u00f3 la condena que le \u00a0fuera \u00a0impuesta \u00a0en \u00a0primera instancia: a once meses de prisi\u00f3n,\u00a0 multa en \u00a0cuant\u00eda \u00a0de \u00a06.94 S.M.L.M.V., as\u00ed como\u00a0 inhabilitaci\u00f3n para el ejercicio \u00a0de \u00a0derechos \u00a0y \u00a0funciones p\u00fablicas por el mismo per\u00edodo de la privativa de la \u00a0libertad, \u00a0a la vez que le concedi\u00f3 la suspensi\u00f3n condicional de la ejecuci\u00f3n \u00a0de la pena. \u00a0\u00a0<\/p>\n<p>DEMANDA \u00a0<\/p>\n<p>Dos \u00a0cargos \u00a0fueron \u00a0postulados \u00a0contra \u00a0la \u00a0sentencia: \u00a0\u00a0<\/p>\n<p>El \u00a0primero de ellos formulado por la v\u00eda de \u00a0la \u00a0violaci\u00f3n \u00a0directa \u00a0dado \u00a0que \u00a0el \u00a0libelista\u00a0 censura la sentencia por \u00a0cuanto \u00a0en \u00a0ella \u00a0s\u00f3lo \u00a0se \u00a0valor\u00f3 \u00a0la actividad riesgosa de la conducci\u00f3n de \u00a0veh\u00edculos \u00a0automotores, \u00a0pero \u00a0a \u00a0la \u00a0vez se dej\u00f3 de evaluar la versi\u00f3n de la \u00a0v\u00edctima \u00a0en \u00a0relaci\u00f3n \u00a0con los riesgos que conlleva la profesi\u00f3n de mec\u00e1nico \u00a0que \u00a0desempe\u00f1aba, \u00a0y \u00a0que a la postre fue la causa de las lesiones que sufri\u00f3; \u00a0pues, \u00a0\u00e9l \u00a0no \u00a0cumpli\u00f3 con los requisitos de seguridad propios de este tipo de \u00a0actividad, \u00a0como \u00a0el \u00a0ponerle \u00a0tacos \u00a0en \u00a0las \u00a0ruedas \u00a0al \u00a0veh\u00edculo \u00a0automotor, \u00a0asegurarse \u00a0de \u00a0tener \u00a0activado el freno de mano, etc, faltas que har\u00edan surgir \u00a0la \u00a0culpa \u00a0de \u00a0la \u00a0v\u00edctima \u00a0como \u00a0la desencadenante de las lesiones y por tanto \u00a0debi\u00f3 exonerarse a CEBALOS ROSERO, seg\u00fan concluye el libelista. \u00a0\u00a0<\/p>\n<p>En \u00a0el cargo segundo \u00a0se \u00a0enuncia \u00a0de \u00a0nuevo la violaci\u00f3n directa de la ley \u00a0sustancial \u00a0a \u00a0partir \u00a0de la falta de verificaci\u00f3n de la prueba aportada por el \u00a0procesado, \u00a0quien, \u00a0seg\u00fan \u00a0afirma \u00a0el \u00a0casacionista, relat\u00f3 de manera clara la \u00a0forma \u00a0en que contrat\u00f3 a Juan Guacales\u00a0 para que revisara los frenos de su \u00a0automotor,\u00a0 \u00a0entreg\u00e1ndoselo \u00a0con la barra de cambios en neutro y con freno \u00a0de \u00a0seguridad \u00a0activado, y que fue \u00e9ste, el mec\u00e1nico v\u00edctima, quien de manera \u00a0imprudente \u00a0y \u00a0negligente \u00a0los \u00a0desactiv\u00f3, para posteriormente darle al cliente \u00a0la\u00a0 \u00a0orden \u00a0de \u00a0encender \u00a0el \u00a0motor \u00a0del rodante que finalmente produjo las \u00a0lesiones, \u00a0relato \u00a0que \u00a0fue \u00a0admitido \u00a0por \u00a0la \u00a0v\u00edctima, \u00a0advierte \u00a0el \u00a0censor. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0agrega \u00a0el \u00a0casacionista, \u00a0el \u00a0juez \u00a0tambi\u00e9n \u00a0pas\u00f3 \u00a0por \u00a0alto el concepto rendido en el juicio por el instructor de \u00a0transporte \u00a0Franklin Armando Salgar Rivera sobre la forma y medidas de seguridad \u00a0que se deb\u00edan implementar al momento de reparar un automotor. \u00a0\u00a0<\/p>\n<p>As\u00ed, advierte el casacionista, la ilegalidad \u00a0del \u00a0fallo \u00a0se \u00a0gener\u00f3 con la omisi\u00f3n valorativa de dichos elementos de prueba \u00a0que\u00a0\u00a0 \u00a0 demostraban \u00a0 que \u00a0 la \u00a0 culpa \u00a0del \u00a0hecho \u00a0reca\u00eda \u00a0sobre \u00a0la \u00a0v\u00edctima,\u00a0 \u00a0 pues \u00a0era \u00a0ella \u00a0quien \u00a0ten\u00eda \u00a0la \u00a0responsabilidad \u00a0sobre \u00a0la \u00a0seguridad \u00a0del \u00a0taller \u00a0en ese momento. Y, al concluir, llama la atenci\u00f3n sobre \u00a0que \u00a0en \u00a0caso \u00a0de \u00a0existir culpa de su defendido, Juzgador debi\u00f3 apoyarse en la \u00a0figura \u00a0de \u00a0la\u00a0 \u00a0compensaci\u00f3n \u00a0de \u00a0culpas, \u00a0y, \u00a0en \u00a0consecuencia, hacer el \u00a0reproche a ambas partes y no solo a una. \u00a0\u00a0<\/p>\n<p>\u00a0 CONSIDERACIONES\u00a0 \u00a0DE\u00a0 LA\u00a0 CORTE \u00a0\u00a0<\/p>\n<p>La \u00a0Sala \u00a0pasa \u00a0a \u00a0estudiar \u00a0los \u00a0aspectos de \u00a0l\u00f3gica \u00a0y \u00a0debida \u00a0argumentaci\u00f3n \u00a0de \u00a0la \u00a0demanda formulada por el defensor de \u00a0H\u00c9CTOR\u00a0 \u00a0GUMERCINDO \u00a0CEBALLOS \u00a0contra \u00a0la sentencia mediante la cual se le \u00a0conden\u00f3 por lesiones personales culposas. \u00a0\u00a0<\/p>\n<p>De \u00a0acuerdo \u00a0en \u00a0la \u00a0previsto \u00a0por \u00a0el inciso \u00a0segundo del art\u00edculo 184 de la ley 906 de 2004, \u00a0\u00a0<\/p>\n<p>\u201cNo \u00a0 ser\u00e1 \u00a0 seleccionada, \u00a0 por \u00a0 auto \u00a0debidamente \u00a0motivado que admite recurso de insistencia presentado por alguno de \u00a0los \u00a0magistrados \u00a0de \u00a0la \u00a0Sala \u00a0o \u00a0por el Ministerio P\u00fablico, la demanda que se \u00a0encuentre \u00a0en cualquiera de los siguientes supuestos: si el demandante carece de \u00a0inter\u00e9s, \u00a0prescinde \u00a0de \u00a0se\u00f1alar \u00a0la \u00a0causal, \u00a0no \u00a0desarrolla \u00a0los \u00a0cargos \u00a0de \u00a0sustentaci\u00f3n \u00a0o cuando de sus contexto se advierte fundamente que no se precisa \u00a0del fallo para cumplir algunas de las finalidades del recurso\u201d \u00a0\u00a0<\/p>\n<p>Se \u00a0observa\u00a0 \u00a0que \u00a0el legislador patrio, \u00a0consciente \u00a0de \u00a0la \u00a0condici\u00f3n \u00a0extraordinaria \u00a0del recurso, facult\u00f3 a la Corte \u00a0para \u00a0que \u00a0realizando \u00a0un \u00a0control \u00a0formal \u00a0a \u00a0la \u00a0demanda, s\u00f3lo admitiera para \u00a0estudio de fondo, o seleccionara, aquellas en las que: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. El \u00a0demandante \u00a0tenga \u00a0inter\u00e9s, \u00a0en \u00a0tanto \u00a0sea \u00a0lesionado con acto \u00a0ilegal o inconstitucional denunciando, \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. El \u00a0 casacionista \u00a0se\u00f1ale \u00a0con \u00a0precisi\u00f3n \u00a0la \u00a0causal \u00a0invocada \u00a0y \u00a0desarrolle de manera correcta los cargos; y, \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. Adem\u00e1s \u00a0de \u00a0lo \u00a0anterior, \u00a0la \u00a0Sala \u00a0advierta \u00a0fundadamente \u00a0que se \u00a0precisa \u00a0 \u00a0del \u00a0 \u00a0fallo \u00a0 para \u00a0 cumplir \u00a0 alguna \u00a0 de \u00a0 las \u00a0 finalidades \u00a0 del \u00a0recurso. \u00a0 \u00a0\u00a0<\/p>\n<p>De \u00a0suerte que en ausencia de alguno de estos \u00a0elementos \u00a0la \u00a0\u00fanica \u00a0opci\u00f3n \u00a0que \u00a0le \u00a0queda a la Corte es\u00a0 abstenerse de \u00a0seleccionar \u00a0la \u00a0demanda, \u00a0por \u00a0medio \u00a0de \u00a0decisi\u00f3n contra la que el legislador \u00a0cre\u00f3 \u00a0el \u00a0mecanismo de insistencia, el que por su misma identidad est\u00e1 llamado \u00a0a \u00a0cuestionar \u00a0la \u00a0argumentaci\u00f3n \u00a0por \u00a0medio \u00a0de \u00a0la \u00a0cual \u00a0la \u00a0Sala consider\u00f3 \u00a0insatisfecha \u00a0 la \u00a0 exigencia \u00a0 normativa \u00a0prevista \u00a0para \u00a0la \u00a0admisi\u00f3n \u00a0de \u00a0la \u00a0demanda. \u00a0\u00a0<\/p>\n<p>Pues \u00a0bien, \u00a0de la sola lectura del libelo se \u00a0advierte \u00a0el \u00a0incumplimiento \u00a0del \u00a0numeral \u00a0segundo en tanto no se desarrollaron \u00a0correctamente los cargos. \u00a0\u00a0<\/p>\n<p>Cuando \u00a0se \u00a0plantea la violaci\u00f3n directa, se \u00a0entiende \u00a0que\u00a0 \u00a0la \u00a0discusi\u00f3n \u00a0queda \u00a0limitada al plano jur\u00eddico, lo cual \u00a0significa\u00a0 \u00a0 que \u00a0 cuando \u00a0se \u00a0invoca \u00a0en \u00a0cualquiera \u00a0de \u00a0sus \u00a0modalidades \u00a0\u2013aplicaci\u00f3n \u00a0indebida, \u00a0falta \u00a0de aplicaci\u00f3n o interpretaci\u00f3n err\u00f3nea-, el recurrente est\u00e1 aceptando \u00a0sin \u00a0miramientos \u00a0la \u00a0apreciaci\u00f3n \u00a0del \u00a0material probatorio generado durante el \u00a0proceso \u00a0realizada \u00a0por \u00a0el \u00a0Tribunal, \u00a0y \u00a0debe, por consiguiente, buscar con la \u00a0argumentaci\u00f3n \u00a0de \u00a0la \u00a0causal, \u00a0demostrar \u00a0el \u00a0equ\u00edvoco en el que incurri\u00f3 el \u00a0juzgador \u00a0respecto \u00a0del \u00a0juicio jur\u00eddico, para terminar\u00a0 concluyendo\u00a0 \u00a0cual\u00a0 \u00a0debi\u00f3 \u00a0ser \u00a0la \u00a0verdadera forma en que se debi\u00f3 realizar.\u00a0 En \u00a0otras \u00a0palabras,\u00a0 \u00a0fungir \u00a0como \u00a0\u201cjuez\u201d y aplicar las normas debidas al \u00a0caso, \u00a0exponiendo\u00a0 \u00a0como \u00a0con \u00a0ellas \u00a0se habr\u00eda llegado a una sentencia de \u00a0sentido diverso al\u00a0 finalmente adoptado. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, \u00a0los \u00a0dos cargos contenidos en la \u00a0demanda \u00a0est\u00e1n \u00a0formulados \u00a0a \u00a0partir \u00a0de \u00a0la \u00a0violaci\u00f3n \u00a0directa \u00a0de \u00a0la \u00a0ley \u00a0sustancial, \u00a0modalidad de yerro respecto de la cual, la Sala ha identificado las \u00a0exigencias \u00a0 \u00a0l\u00f3gicas \u00a0 \u00a0que \u00a0 \u00a0debe \u00a0 cumplir \u00a0 su \u00a0 planteamiento1: \u00a0\u00a0<\/p>\n<p>\u201cViolaci\u00f3n directa. \u00a0<\/p>\n<p>Cuando se trata de este tipo de controversia, \u00a0que \u00a0refiere \u00a0el \u00a0supuesto \u00a0desconocimiento o tergiversaci\u00f3n de lo que la norma \u00a0sustancial \u00a0consagra, se hace menester, para que la Sala comprenda la naturaleza \u00a0y \u00a0magnitud \u00a0del \u00a0yerro, \u00a0cumplir unos m\u00ednimos requisitos de sustentaci\u00f3n, que \u00a0han \u00a0 \u00a0 \u00a0 \u00a0 sido \u00a0 \u00a0 \u00a0 \u00a0resumidos \u00a0 \u00a0 \u00a0 \u00a0as\u00ed2: \u00a0\u00a0<\/p>\n<p>\u201c2.1. \u00a0Afirmar y probar que el juzgador de \u00a0segunda \u00a0instancia \u00a0ha \u00a0incurrido \u00a0en error por falta de aplicaci\u00f3n (exclusi\u00f3n \u00a0evidente \u00a0o \u00a0infracci\u00f3n \u00a0directa), \u00a0por \u00a0aplicaci\u00f3n \u00a0indebida (falso juicio de \u00a0selecci\u00f3n) \u00a0o \u00a0por interpretaci\u00f3n err\u00f3nea (sobre la existencia material sobre \u00a0la validez o sobre la existencia o alcance) de la ley sustancial. \u00a0\u00a0<\/p>\n<p>2.2. \u00a0Abstenerse \u00a0de reprochar la prueba, es \u00a0decir, \u00a0le \u00a0compete \u00a0aceptar \u00a0la apreciaci\u00f3n que de ella ha hecho el fallador y \u00a0conformarse \u00a0de \u00a0manera \u00a0absoluta \u00a0con la declaraci\u00f3n de los hechos vertida por \u00a0\u00e9ste. \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Realizar un \u00a0estudio puramente jur\u00eddico de la sentencia. \u00a0 \u00a0\u00a0<\/p>\n<p>2.4. \u00a0Si \u00a0como \u00a0consecuencia \u00a0de la err\u00f3nea \u00a0interpretaci\u00f3n \u00a0de \u00a0la\u00a0 \u00a0ley, \u00a0esta \u00a0se \u00a0deja \u00a0de \u00a0aplicar, \u00a0o \u00a0se \u00a0aplica \u00a0indebidamente, \u00a0debe \u00a0dirigir \u00a0su acusaci\u00f3n hacia una de estas dos hip\u00f3tesis y \u00a0no \u00a0hacia \u00a0la \u00a0interpretaci\u00f3n \u00a0equivocada \u00a0de \u00a0la \u00a0ley \u00a0pues \u00a0lo importante, en \u00a0\u00faltimas, \u00a0es \u00a0la \u00a0decisi\u00f3n tomada por el juez: no aplicar la norma o aplicarla \u00a0indebidamente. \u00a0\u00a0<\/p>\n<p>2.5. \u00a0Si \u00a0se predica aplicaci\u00f3n indebida de \u00a0una \u00a0norma, \u00a0tiene que precisar la norma inadecuadamente utilizada y aquella que \u00a0en su lugar debe ser atribuida. \u00a0\u00a0<\/p>\n<p>2.6. Respecto de una misma disposici\u00f3n legal \u00a0no \u00a0puede predicar simult\u00e1neamente falta de aplicaci\u00f3n y aplicaci\u00f3n indebida. \u00a0\u00a0<\/p>\n<p>2.7. \u00a0Indicar \u00a0de \u00a0forma clara y precisa los \u00a0fundamentos de la causal. \u00a0\u00a0<\/p>\n<p>2.8. \u00a0Citar \u00a0las \u00a0normas \u00a0que \u00a0se \u00a0estiman \u00a0infringidas. \u00a0\u00a0<\/p>\n<p>2.9. Si por esta v\u00eda el proponente reprocha \u00a0al \u00a0juzgador \u00a0el tratamiento impartido al principio de duda, tiene que demostrar \u00a0que \u00a0en \u00a0la \u00a0sentencia \u00a0el fallador ha reconocido formalmente la presencia de la \u00a0incertidumbre \u00a0y \u00a0que, sin embargo, ha condenado, con lo cual ha incurrido en la \u00a0falta \u00a0de \u00a0aplicaci\u00f3n \u00a0del art\u00edculo 445 del C\u00f3digo de Procedimiento Penal.\u201d \u00a0\u00a0<\/p>\n<p>En \u00a0punto \u00a0de \u00a0evaluar \u00a0dichas exigencias en \u00a0relaci\u00f3n \u00a0con \u00a0la \u00a0demanda presentada por el defensor de CEBALLOS ROSERO, surge \u00a0evidente \u00a0que \u00a0el \u00a0casacionista cuestion\u00f3 la valoraci\u00f3n probatoria pues en las \u00a0dos \u00a0censuras \u00a0recrimin\u00f3 \u00a0al \u00a0juzgador haber dejado de apreciar las pruebas que \u00a0conduc\u00edan, \u00a0seg\u00fan \u00a0su \u00a0propia \u00a0lectura, \u00a0a \u00a0proferir absoluci\u00f3n a favor de su \u00a0asistido, \u00a0con lo cual se abandon\u00f3 la l\u00f3gica propia de dicha causal e invadi\u00f3 \u00a0los \u00a0campos \u00a0propios \u00a0de \u00a0la violaci\u00f3n indirecta por falso juicio de existencia \u00a0por \u00a0 omisi\u00f3n, \u00a0 sin \u00a0tampoco \u00a0desarrollar \u00a0ning\u00fan \u00a0ataque \u00a0en \u00a0ese \u00a0contexto. \u00a0\u00a0<\/p>\n<p>La \u00a0argumentaci\u00f3n del primer ataque gira en \u00a0torno \u00a0a \u00a0la \u00a0ausencia \u00a0de \u00a0valoraci\u00f3n \u00a0de la versi\u00f3n de la v\u00edctima, omisi\u00f3n \u00a0realizada \u00a0por \u00a0el juez frente al riesgo que conllevaba la actividad laboral que \u00a0desempe\u00f1aba, \u00a0valoraci\u00f3n\u00a0 \u00a0totalmente \u00a0inapropiada \u00a0dentro \u00a0de \u00a0la causal \u00a0invocada \u00a0como \u00a0arriba \u00a0se \u00a0indic\u00f3, \u00a0al \u00a0establecerse que el censor est\u00e1 en la \u00a0obligaci\u00f3n \u00a0de \u00a0limitar \u00a0su \u00a0ataque \u00a0a \u00a0la \u00a0base \u00a0jur\u00eddica del fallo objeto de \u00a0censura. \u00a0\u00a0<\/p>\n<p>En \u00a0el \u00a0segundo \u00a0cargo se incurre en el mismo \u00a0yerro, \u00a0toda \u00a0vez que el libelista propone un debate en derecho, pero no va m\u00e1s \u00a0all\u00e1 \u00a0de \u00a0unos \u00a0an\u00e1lisis \u00a0probatorios, \u00a0advirtiendo igualmente que se debieron \u00a0tener \u00a0en cuenta para motivar una sentencia de naturaleza absolutoria\u00a0 unos \u00a0elementos \u00a0de \u00a0convicci\u00f3n \u00a0que no fueron valorados, como fueron la versi\u00f3n del \u00a0acusado \u00a0 \u00a0as\u00ed \u00a0 \u00a0como \u00a0 \u00a0el \u00a0 \u00a0testimonio \u00a0 de \u00a0 un \u00a0 experto \u00a0 en \u00a0 seguridad \u00a0automotriz. \u00a0\u00a0<\/p>\n<p>Como si fuera poco, el casacionista present\u00f3 \u00a0una \u00a0lectura \u00a0sesgada \u00a0de \u00a0su \u00a0propia \u00a0forma, \u00a0interesada por supuesto,\u00a0 de \u00a0percibir \u00a0los \u00a0hechos, \u00a0y \u00a0pretende \u00a0por \u00a0la \u00a0v\u00eda \u00a0del \u00a0recurso \u00a0extraordinario \u00a0imponerla \u00a0a esta colegiatura, evadiendo el an\u00e1lisis riguroso de los institutos \u00a0jur\u00eddicos \u00a0involucrados\u00a0 \u00a0en \u00a0su \u00a0inconformidad, \u00a0sin que su escrito logre \u00a0diferenciarse de un alegato propio de las instancias. \u00a0\u00a0<\/p>\n<p>As\u00ed, \u00a0pues, incumplida la exigencia segunda \u00a0del \u00a0casacionista, \u00a0relacionada \u00a0con el se\u00f1alamiento de la causal acertada as\u00ed \u00a0como \u00a0 el \u00a0desarrollo \u00a0correcto \u00a0de \u00a0los \u00a0cargos, \u00a0se \u00a0inadmitir\u00e1 \u00a0la \u00a0demanda. \u00a0\u00a0<\/p>\n<p>Finalmente,\u00a0 \u00a0aun \u00a0cuando se pasaran por \u00a0alto \u00a0los \u00a0errores \u00a0de \u00a0t\u00e9cnica \u00a0del \u00a0recurso, \u00a0esta \u00a0Sala no encuentra ning\u00fan \u00a0elemento \u00a0que \u00a0le \u00a0indique la existencia de ilegalidad o inconstitucionalidad de \u00a0la \u00a0sentencia que hagan necesario un fallo para el cumplimiento de alguna de las \u00a0finalidades del recurso. \u00a0\u00a0<\/p>\n<p>Como \u00a0quiera \u00a0que \u00a0seg\u00fan lo dispuesto por el \u00a0inciso \u00a0segundo \u00a0del art\u00edculo 184 del C\u00f3digo de Procedimiento Penal, contra la \u00a0decisi\u00f3n \u00a0de \u00a0no \u00a0seleccionar \u00a0la \u00a0demanda procede el mecanismo de insistencia, \u00a0conviene \u00a0reiterar \u00a0el \u00a0precedente \u00a0jurisprudencial3 \u00a0 que \u00a0 delinea \u00a0sus \u00a0ribetes \u00a0procedimentales, \u00a0 ante \u00a0 la \u00a0omisi\u00f3n \u00a0legislativa \u00a0de \u00a0la \u00a0definici\u00f3n \u00a0de \u00a0su \u00a0tr\u00e1mite. \u00a0\u00a0<\/p>\n<p>En \u00a0 m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0 la \u00a0 Corte \u00a0 Suprema \u00a0 de \u00a0Justicia, \u00a0Sala \u00a0de \u00a0Casaci\u00f3n \u00a0Penal. \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>Inadmitir la demanda \u00a0presentada por el defensor de H\u00c9CTOR GUMERCINDO CEBALLOS ROSERO. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta decisi\u00f3n procede el mecanismo \u00a0de \u00a0insistencia \u00a0a la luz de lo dispuesto en el inciso segundo del art\u00edculo 184 \u00a0del C\u00f3digo de Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese, c\u00famplase. \u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0<\/p>\n<p>JOS\u00c9 \u00a0 \u00a0 \u00a0 LUIS \u00a0 \u00a0 \u00a0 BARCEL\u00d3 \u00a0CAMACHO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0FERNANDO ALBERTO CASTRO \u00a0CABALLERO\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 EUGENIO FERN\u00c1NDEZ \u00a0CARLIER\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0MAR\u00cdA DEL ROSARIO GONZ\u00c1LEZ MU\u00d1OZ\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0GUSTAVO \u00a0ENRIQUE MALO \u00a0FERN\u00c1NDEZ\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 EYDER \u00a0PATI\u00d1O \u00a0 CABRERA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>LUIS GUILLERMO SALAZAR OTERO \u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 Auto \u00a0de 3 de diciembre de 2009, radicado 32824. \u00a0\u00a0<\/p>\n<p>2\u00a0 \u00a0Auto del 30 de noviembre de 1999, radicado 14535. \u00a0\u00a0<\/p>\n<p>3 Auto \u00a0de diciembre 12 de 2005, dentro del radicado 24.322. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0\u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente \u00a0 JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0 Aprobado acta N\u00ba 419 \u00a0 \u00a0 \u00a0 Bogot\u00e1 \u00a0D.C., \u00a0once \u00a0de diciembre de dos mil \u00a0trece. \u00a0\u00a0 V \u00a0 I \u00a0 S \u00a0 T \u00a0 O \u00a0 S \u00a0\u00a0 La \u00a0sala \u00a0se \u00a0ocupa \u00a0de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-27355","post","type-post","status-publish","format-standard","hentry","category-21"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/27355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=27355"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/27355\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=27355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=27355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=27355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}