{"id":25537,"date":"2023-09-12T19:49:10","date_gmt":"2023-09-12T19:49:10","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3710720-11-13\/"},"modified":"2023-09-12T19:49:10","modified_gmt":"2023-09-12T19:49:10","slug":"3710720-11-13","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3710720-11-13\/","title":{"rendered":"37107(20-11-13)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>MAGISTRADO PONENTE \u00a0<\/p>\n<p>EYDER PATI\u00d1O CABRERA \u00a0<\/p>\n<p>Aprobado: Acta No. 386- \u00a0<\/p>\n<p>Bogot\u00e1. \u00a0D.C., \u00a0veinte (20) de noviembre de dos mil trece \u00a0(2013) \u00a0\u00a0<\/p>\n<p>MOTIVO DE LA DECISI\u00d3N \u00a0<\/p>\n<p>Decide \u00a0la \u00a0Sala \u00a0el \u00a0recurso \u00a0de \u00a0casaci\u00f3n \u00a0interpuesto \u00a0por \u00a0el defensor de NATALY DUARTE, contra la sentencia proferida el \u00a07 \u00a0de mayo de 2011 por el Tribunal Superior de Bogot\u00e1, mediante la cual revoc\u00f3 \u00a0el \u00a0fallo \u00a0absolutorio \u00a0del \u00a011 \u00a0de abril del mismo a\u00f1o, dictado por el Juzgado \u00a0Segundo \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0esta \u00a0ciudad \u00a0y, \u00a0en \u00a0su lugar, conden\u00f3 a la \u00a0procesada \u00a0como \u00a0autora \u00a0del \u00a0delito \u00a0de actos sexuales abusivos con menor de 14 \u00a0a\u00f1os agravado en concurso homog\u00e9neo. \u00a0\u00a0<\/p>\n<p>HECHOS Y ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>1. Seg\u00fan denuncia formulada por la madre del \u00a0menor \u00a0M.A.L.O.1, \u00a0de 6 a\u00f1os de edad, cuando el ni\u00f1o iba de visita a la casa de su \u00a0padre, \u00a0la compa\u00f1era de \u00e9ste, NATALY DUARTE, le manipulaba el pene en momentos \u00a0en \u00a0que \u00a0lo \u00a0ba\u00f1aba \u00a0o lo vest\u00eda y en otra oportunidad se subi\u00f3 la falda y lo \u00a0oblig\u00f3 \u00a0a \u00a0tocarle \u00a0los \u00a0genitales, \u00a0amenaz\u00e1ndolo \u00a0con \u00a0pegarle \u00a0si \u00a0llegaba a \u00a0contar. \u00a0\u00a0<\/p>\n<p>Los hechos ocurrieron en la ciudad de Bogot\u00e1, \u00a0en el segundo semestre del a\u00f1o 2005. \u00a0\u00a0<\/p>\n<p>2. En audiencia preliminar celebrada el 16 de \u00a0febrero \u00a0de \u00a02007, \u00a0el \u00a0Juzgado \u00a045 \u00a0Penal Municipal con funciones de control de \u00a0garant\u00edas \u00a0imparti\u00f3 \u00a0legalidad \u00a0a \u00a0la captura de NATALY DUARTE, as\u00ed como a la \u00a0imputaci\u00f3n \u00a0por \u00a0el \u00a0delito \u00a0de \u00a0acto \u00a0sexual \u00a0abusivo \u00a0con \u00a0menor \u00a0de 14 a\u00f1os \u00a0agravado, \u00a0que \u00a0no fue aceptada por la encartada, a quien no se le impuso medida \u00a0de \u00a0aseguramiento2. \u00a0\u00a0<\/p>\n<p>3. \u00a0Presentado el escrito de acusaci\u00f3n el 12 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 marzo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 siguiente3, \u00a0el Juzgado Segundo Penal del \u00a0Circuito \u00a0de \u00a0esta \u00a0ciudad \u00a0llev\u00f3 \u00a0a \u00a0cabo \u00a0las \u00a0audiencias \u00a0de formulaci\u00f3n de \u00a0acusaci\u00f3n \u00a0 \u00a0el \u00a0 \u00a023 \u00a0 \u00a0de \u00a0 \u00a0mayo \u00a0 \u00a0de \u00a0 \u00a020074, \u00a0la \u00a0preparatoria \u00a0el \u00a01\u00ba de \u00a0abril \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del \u00a0 \u00a0 \u00a0 \u00a0 mismo \u00a0 \u00a0 \u00a0 \u00a0 a\u00f1o5 \u00a0 y \u00a0la \u00a0de \u00a0juicio \u00a0oral \u00a0en \u00a0sesiones \u00a0del \u00a010 \u00a0de \u00a0junio de 2008, 7 de mayo, 24 de agosto y 22 de octubre de \u00a02009, \u00a08, \u00a021 \u00a0de \u00a0septiembre \u00a0y 8 de noviembre de 2010 y 14 de febrero de 2011, \u00a0fecha \u00a0\u00faltima \u00a0en \u00a0la \u00a0que \u00a0se \u00a0emiti\u00f3 \u00a0el \u00a0sentido \u00a0del \u00a0fallo \u00a0de \u00a0car\u00e1cter \u00a0absolutorio6. \u00a0\u00a0<\/p>\n<p>El \u00a08 de abril de esa anualidad, se dict\u00f3 la \u00a0sentencia \u00a0por \u00a0cuyo \u00a0medio se absolvi\u00f3 a NATALY DUARTE del cargo formulado por \u00a0la \u00a0 fiscal\u00eda7. \u00a0\u00a0<\/p>\n<p>4. \u00a0El \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1, \u00a0al \u00a0resolver \u00a0el recurso de apelaci\u00f3n interpuesto por el apoderado de la v\u00edctima y \u00a0por \u00a0 la \u00a0 fiscal\u00eda, \u00a0revoc\u00f3 \u00a0la \u00a0decisi\u00f3n \u00a0del \u00a0A \u00a0quo \u00a0y, \u00a0en \u00a0su \u00a0lugar, \u00a0conden\u00f3 a la enjuiciada como \u00a0autora \u00a0del delito de actos sexuales abusivos con menor de 14 a\u00f1os agravado, en \u00a0concurso \u00a0homog\u00e9neo. \u00a0En consecuencia, le impuso la pena principal de ochenta y \u00a0cinco \u00a0(85) \u00a0meses \u00a0de \u00a0prisi\u00f3n \u00a0y, \u00a0por \u00a0el \u00a0mismo \u00a0tiempo, \u00a0la \u00a0accesoria \u00a0de \u00a0inhabilitaci\u00f3n \u00a0para \u00a0el \u00a0ejercicio \u00a0de \u00a0derechos \u00a0y \u00a0funciones \u00a0p\u00fablicas, sin \u00a0derecho \u00a0a \u00a0la \u00a0suspensi\u00f3n \u00a0condicional \u00a0de \u00a0la \u00a0ejecuci\u00f3n \u00a0de la pena ni a la \u00a0prisi\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 domiciliaria8. \u00a0\u00a0<\/p>\n<p>5. \u00a0 El \u00a012 \u00a0de \u00a0diciembre \u00a0de \u00a02011, \u00a0esta \u00a0Corporaci\u00f3n \u00a0 super\u00f3 \u00a0 los \u00a0 defectos \u00a0l\u00f3gico-argumentativos \u00a0de \u00a0la \u00a0demanda \u00a0presentada \u00a0por \u00a0el \u00a0defensor \u00a0de \u00a0NATALY \u00a0DUARTE \u00a0y \u00a0la \u00a0admiti\u00f3 con el \u00fanico \u00a0prop\u00f3sito de hacer efectivos los fines del recurso extraordinario. \u00a0\u00a0<\/p>\n<p>6. \u00a0 Celebrada \u00a0la \u00a0audiencia \u00a0p\u00fablica \u00a0de \u00a0sustentaci\u00f3n, se procede a resolver de fondo. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>Con \u00a0apoyo en la causal tercera de casaci\u00f3n, \u00a0el \u00a0impugnante \u00a0censura \u00a0la \u00a0sentencia \u00a0del \u00a0Tribunal \u00a0por \u00a0error de hecho en la \u00a0modalidad \u00a0de \u00a0falso \u00a0raciocinio, que condujo a desconocer\u00a0 el principio de \u00a0presunci\u00f3n \u00a0de \u00a0inocencia \u00a0y \u00a0los \u00a0art\u00edculos \u00a0373 \u00a0y \u00a0380 \u00a0de \u00a0la \u00a0Ley \u00a0906 de \u00a02004. \u00a0\u00a0<\/p>\n<p>Tras \u00a0destacar \u00a0algunas expresiones del menor \u00a0v\u00edctima, \u00a0tanto \u00a0en \u00a0la \u00a0entrevista \u00a0psicol\u00f3gica \u00a0realizada el 5 de febrero de \u00a02007, \u00a0como \u00a0en \u00a0el \u00a0juicio \u00a0oral, \u00a0encuentra il\u00f3gico e inconsistente que en la \u00a0\u00faltima \u00a0diligencia, \u00a0cuando ya hab\u00edan pasado seis a\u00f1os desde la ocurrencia de \u00a0los \u00a0hechos, \u00a0mencionara \u00a0con \u00a0precisi\u00f3n \u00a0el \u00a0lugar \u00a0donde \u00a0vivi\u00f3, pero no los \u00a0detalles \u00a0 que \u00a0 describi\u00f3 \u00a0 a \u00a0 la \u00a0psic\u00f3loga, \u00a0referentes \u00a0a \u00a0los \u00a0supuestos \u00a0tocamientos, \u00a0\u201cque es donde este menor hace emerger \u00a0la duda totalmente\u201d. \u00a0\u00a0<\/p>\n<p>Las reglas de la l\u00f3gica y de la experiencia, \u00a0ense\u00f1an \u00a0que \u00a0la memoria de las personas se va perdiendo con el paso del tiempo \u00a0y \u00a0es \u00a0muy \u00a0improbable \u00a0que \u00a0el \u00a0infante \u00a0haya \u00a0obtenido nuevos recuerdos de los \u00a0presuntos insucesos traum\u00e1ticos. \u00a0\u00a0<\/p>\n<p>Con \u00a0la \u00a0declaraci\u00f3n de Alirio Enrique Lemus \u00a0Sarmiento \u00a0 \u2013padre \u00a0del \u00a0afectado-, \u00a0se \u00a0demostr\u00f3 \u00a0que \u00a0para \u00a0la \u00a0fecha de los \u00a0acontecimientos \u00a0el \u00a0ni\u00f1o \u00a0ya no viv\u00eda en su casa, pues seg\u00fan inform\u00f3, el 23 \u00a0de \u00a0septiembre de 2005 puso en conocimiento de las autoridades judiciales que el \u00a01\u00ba \u00a0de \u00a0junio \u00a0anterior, \u00a0la \u00a0se\u00f1ora \u00a0Orjuela \u00a0Carvajal se hab\u00eda llevado a su \u00a0hijo. \u00a0\u00a0<\/p>\n<p>Entonces, \u00a0dice \u00a0el censor, no es l\u00f3gico que \u00a0\u00e9ste \u00a0manifestara \u00a0dolor \u00a0en el pene cuando ya viv\u00eda con su mam\u00e1 y que uno de \u00a0los tocamientos ocurri\u00f3 cuando llegaba del colegio. \u00a0\u00a0<\/p>\n<p>De \u00a0contera, \u00a0se muestra fuera de contexto el \u00a0indicio \u00a0de oportunidad que dedujo el Tribunal aduciendo que la encartada tuvo a \u00a0su \u00a0lado \u00a0al \u00a0menor \u00a0para \u00a0la \u00e9poca de los insucesos, porque basta observar las \u00a0fechas \u00a0de las rec\u00edprocas denuncias, en especial, la formulada por el padre del \u00a0ni\u00f1o. \u00a0\u00a0<\/p>\n<p>En cuanto a los dict\u00e1menes psicol\u00f3gicos, le \u00a0merece \u00a0especial \u00a0consideraci\u00f3n \u00a0el \u00a0presentado \u00a0por la defensa, dado que en un \u00a0estudio \u00a0juicioso la experta razon\u00f3 que el testimonio del menor no era cre\u00edble \u00a0y, adem\u00e1s, tiene mayor experiencia que la perito de la Sijin. \u00a0\u00a0<\/p>\n<p>Concluye \u00a0 \u00a0que \u00a0 \u00a0si \u00a0 el \u00a0 Ad \u00a0quem \u00a0hubiese \u00a0aplicado \u00a0las m\u00ednimas \u00a0reglas \u00a0de \u00a0la \u00a0l\u00f3gica, \u00a0habr\u00eda confirmado la sentencia absolutoria de primera \u00a0instancia, la cual se ajusta a derecho. \u00a0\u00a0<\/p>\n<p>En \u00a0ese \u00a0sentido, \u00a0solicita \u00a0se case el fallo \u00a0impugnado. \u00a0\u00a0<\/p>\n<p>AUDIENCIA DE SUSTENTACI\u00d3N \u00a0<\/p>\n<p>1. \u00a0La \u00a0defensa. \u00a0El \u00a0recurrente \u00a0en \u00a0casaci\u00f3n, manifiesta que no tiene \u00a0argumentos \u00a0adicionales a los expuestos en su demanda, los cuales se deben tener \u00a0en cuenta. \u00a0\u00a0<\/p>\n<p>2. \u00a0La \u00a0Fiscal\u00eda. \u00a0El \u00a0se\u00f1or \u00a0Fiscal Delegado ante la Corte comienza por \u00a0referir \u00a0que, \u00a0en \u00a0punto \u00a0del error de hecho por falso raciocinio, el demandante \u00a0ataca \u00a0la \u00a0credibilidad \u00a0del \u00a0relato \u00a0suministrado \u00a0por \u00a0el \u00a0menor v\u00edctima, sin \u00a0evidenciar \u00a0en \u00a0qu\u00e9 \u00a0consisti\u00f3 \u00a0el \u00a0yerro \u00a0y su incidencia en el serio estudio \u00a0desarrollado por el Tribunal. \u00a0\u00a0<\/p>\n<p>Se apoya en lo dicho por esta Sala dentro del \u00a0radicado \u00a027946 \u00a0del \u00a06 de septiembre de 2007, para destacar las falencias de la \u00a0censura, \u00a0donde \u00a0no \u00a0se \u00a0identifican \u00a0los \u00a0par\u00e1metros \u00a0de \u00a0la sana cr\u00edtica que \u00a0resultaron vulnerados, pues a ellos se refiere sin distingo alguno. \u00a0\u00a0<\/p>\n<p>Tras \u00a0recordar \u00a0que \u00a0la Corte ha definido una \u00a0l\u00ednea \u00a0jurisprudencial \u00a0en \u00a0la \u00a0que \u00a0excepcionalmente \u00a0no \u00a0se \u00a0requiere \u00a0de \u00a0la \u00a0repetici\u00f3n \u00a0del \u00a0juicio, \u00a0aduce \u00a0que, \u00a0en \u00a0este caso, la declaraci\u00f3n del ni\u00f1o \u00a0debi\u00f3 \u00a0ser \u00a0objeto \u00a0de valoraci\u00f3n teniendo en cuenta su condici\u00f3n de v\u00edctima \u00a0del delito. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0tanto, \u00a0conforme a la jurisprudencia \u00a0penal \u00a0y \u00a0constitucional, \u00a0no \u00a0puede ser de recibo el argumento del Ad \u00a0quem, \u00a0seg\u00fan \u00a0el \u00a0cual, \u201cla \u00a0no \u00a0apreciaci\u00f3n \u00a0de \u00a0la \u00a0declaraci\u00f3n \u00a0del \u00a0menor no genera \u00a0afectaci\u00f3n \u00a0 de \u00a0 los \u00a0 derechos \u00a0y \u00a0garant\u00edas \u00a0fundamentales \u00a0de \u00a0las \u00a0partes \u00a0intervinientes\u201d, \u00a0porque \u00a0para \u00a0sustentar que no era \u00a0necesario \u00a0retrotraer \u00a0lo \u00a0actuado, \u00a0o por lo menos aquella sesi\u00f3n en la que no \u00a0intervino \u00a0directamente \u00a0la \u00a0juez a cargo del desarrollo de debate y emisi\u00f3n el \u00a0fallo, \u00a0no \u00a0se hace necesario excluir de la valoraci\u00f3n probatoria el testimonio \u00a0de \u00a0la \u00a0v\u00edctima, sino simplemente argumentar que la decisi\u00f3n no se soportar\u00eda \u00a0en \u00e9l. \u00a0\u00a0<\/p>\n<p>Agrega que de acuerdo con los lineamientos de \u00a0esta \u00a0Corporaci\u00f3n, \u00a0contenidos \u00a0en \u00a0los radicados 26411 de 2007, 28742 de 2008, \u00a029678 \u00a0de 2008 y 32103 de 2009, la informaci\u00f3n que suministre un menor v\u00edctima \u00a0de \u00a0abuso sexual a aquellas personas especializadas en una determinada \u00e1rea del \u00a0conocimiento \u00a0que \u00a0presta \u00a0servicio t\u00e9cnico-cient\u00edfico a la administraci\u00f3n de \u00a0justicia, \u00a0es de vital importancia para esclarecer la verdad de lo acontecido lo \u00a0m\u00e1s \u00a0cerca \u00a0posible \u00a0a \u00a0la \u00a0realidad, \u00a0teniendo \u00a0en cuenta que en esta clase de \u00a0injustos, \u00a0los \u00a0actores \u00a0acuden a escenarios en los cuales se encuentran a solas \u00a0con su v\u00edctima, para no ser descubiertos. \u00a0\u00a0<\/p>\n<p>A \u00a0partir \u00a0de all\u00ed, dicha rese\u00f1a comienza a \u00a0ser \u00a0 parte \u00a0del \u00a0conocimiento \u00a0de \u00a0esas \u00a0personas \u00a0especializadas, \u00a0quienes \u00a0se \u00a0encargar\u00e1n \u00a0de \u00a0evaluar su contenido, la forma como se percibi\u00f3, la coherencia \u00a0y \u00a0 la \u00a0 l\u00f3gica \u00a0 con \u00a0 que \u00a0 se \u00a0 narr\u00f3, \u00a0 para \u00a0 luego \u00a0 dar \u00a0 su \u00a0 concepto \u00a0t\u00e9cnico-cient\u00edfico, \u00a0el \u00a0que \u00a0luego \u00a0ser\u00e1 introducido al proceso en el juicio \u00a0oral mediante la prueba pericial. \u00a0\u00a0<\/p>\n<p>Conforme \u00a0a lo anterior, se puede llegar a la \u00a0conclusi\u00f3n \u00a0expuesta \u00a0por \u00a0el Tribunal, en el entendido que el concepto emitido \u00a0en \u00a0el \u00a0juicio \u00a0oral \u00a0por \u00a0la \u00a0doctora Martha Janneth Fuentes Murillo constituye \u00a0prueba \u00a0pericial \u00a0a \u00a0trav\u00e9s \u00a0de \u00a0la \u00a0cual, \u00a0de \u00a0manera \u00a0directa, \u00a0se aport\u00f3 el \u00a0conocimiento \u00a0que \u00a0adquiri\u00f3 \u00a0del \u00a0relato \u00a0del \u00a0menor que ella examin\u00f3. De esta \u00a0manera, \u00a0pronto se advertir\u00e1 que el Tribunal valor\u00f3 claramente la informaci\u00f3n \u00a0suministrada por la psic\u00f3loga experta. \u00a0\u00a0<\/p>\n<p>Tales \u00a0 manifestaciones, \u00a0 producidas \u00a0como \u00a0consecuencia \u00a0del \u00a0an\u00e1lisis \u00a0especializado \u00a0integrado por la sana cr\u00edtica, que \u00a0tuvo \u00a0en \u00a0cuenta el juez plural para revocar el fallo de primera instancia y, en \u00a0su \u00a0lugar, proferir uno de car\u00e1cter condenatorio, no fueron desvirtuadas por la \u00a0defensa, \u00a0como \u00a0mal \u00a0lo \u00a0entiende el censor al pretender que se le otorgue mayor \u00a0credibilidad \u00a0a \u00a0la perito que tambi\u00e9n declar\u00f3 en el juicio oral, a t\u00edtulo de \u00a0descargo, \u00a0pero \u00a0no \u00a0con \u00a0el \u00a0mismo \u00a0nivel \u00a0cient\u00edfico \u00a0expuesto por la doctora \u00a0Fuentes Murillo. \u00a0\u00a0<\/p>\n<p>En \u00a0criterio del delegado de la fiscal\u00eda, la \u00a0defensa \u00a0desacierta en su intento de demeritar el dicho del menor, pues no tiene \u00a0en \u00a0cuenta \u00a0que \u00a0en \u00a0trat\u00e1ndose \u00a0de \u00a0la \u00a0valoraci\u00f3n \u00a0de \u00a0un \u00a0testimonio \u00a0y \u00a0la \u00a0informaci\u00f3n \u00a0suministrada \u00a0por \u00a0\u00e9l \u00a0a \u00a0la psic\u00f3loga, se deben apreciar cuatro \u00a0aspectos: \u00a0i) quien declara es un ni\u00f1o de cinco (5) a\u00f1os; ii) el mismo refiere \u00a0temas \u00a0puntuales \u00a0y \u00a0constantes como es el hecho de la manipulaci\u00f3n corporal de \u00a0la \u00a0que fue objeto, el escenario y la persona que la realizaba, refiri\u00e9ndose en \u00a0lo \u00a0sustancial \u00a0con \u00a0claridad; \u00a0iii) la jurisprudencia ha entendido que en punto \u00a0del \u00a0testimonio de menores, suele ser muy dif\u00edcil fijar fechas exactas y se les \u00a0puede \u00a0confundir dependiendo de la forma como sean entrevistados o interrogados, \u00a0pero \u00a0es \u00a0muy \u00a0improbable \u00a0que se preste a confusi\u00f3n el conocimiento vivencial; \u00a0iv) \u00a0la \u00a0valoraci\u00f3n de la informaci\u00f3n que suministre un infante, se debe hacer \u00a0con especial cuidado. \u00a0\u00a0<\/p>\n<p>En \u00a0ese \u00a0orden, resulta intrascendente si los \u00a0hechos \u00a0se \u00a0presentaron \u00a0dos \u00a0o \u00a0cinco \u00a0veces, porque lo cierto es que el delito \u00a0ocurri\u00f3, as\u00ed la manipulaci\u00f3n hubiese sido una sola. \u00a0\u00a0<\/p>\n<p>Reitera \u00a0 su \u00a0 solicitud \u00a0de \u00a0no \u00a0casar \u00a0la \u00a0sentencia. \u00a0\u00a0<\/p>\n<p>3. \u00a0El \u00a0Ministerio \u00a0P\u00fablico. \u00a0La \u00a0se\u00f1ora \u00a0Procuradora \u00a0Tercera \u00a0Delegada \u00a0para la Casaci\u00f3n Penal \u00a0precisa \u00a0que, \u00a0como \u00a0la \u00a0demanda \u00a0fue \u00a0admitida \u00a0para la efectividad del derecho \u00a0material \u00a0y \u00a0el \u00a0respeto \u00a0a \u00a0las \u00a0garant\u00edas, es esencial determinar si existi\u00f3 \u00a0vulneraci\u00f3n \u00a0al principio de inmediaci\u00f3n de la prueba en la producci\u00f3n de los \u00a0fallos \u00a0de \u00a0primera y segunda instancia, como quiera que el testimonio del menor \u00a0afectado \u00a0no fue practicado ante el juez que profiri\u00f3 el sentido del fallo y en \u00a0\u00faltimas lo redact\u00f3. \u00a0\u00a0<\/p>\n<p>La Corte ha dicho en varias oportunidades, que \u00a0ese \u00a0tipo \u00a0de circunstancias no acarrea indefectiblemente la nulidad del juicio, \u00a0porque \u00a0es \u00a0posible \u00a0salvar \u00a0la \u00a0inmediaci\u00f3n recurriendo a la obtenci\u00f3n de los \u00a0registros, \u00a0m\u00e1xime \u00a0si \u00a0la \u00a0v\u00edctima \u00a0es un ni\u00f1o, ni\u00f1a o adolescente, como se \u00a0dijo en los radicados 27192 de 2008 y 32556 de 2010. \u00a0\u00a0<\/p>\n<p>Si \u00a0bien \u00a0en \u00a0este \u00a0caso \u00a0la \u00a0declaraci\u00f3n de \u00a0M.A.L.O. \u00a0fue \u00a0observada \u00a0por \u00a0un \u00a0juez \u00a0distinto al que profiri\u00f3 la sentencia, \u00a0considera \u00a0que \u00a0existe \u00a0un \u00a0error \u00a0en \u00a0el \u00a0Tribunal al no apreciar esta prueba y \u00a0desecharla \u00a0 como \u00a0 si \u00a0 se \u00a0 hubiese \u00a0obtenido \u00a0con \u00a0violaci\u00f3n \u00a0de \u00a0garant\u00edas \u00a0fundamentales. \u00a0\u00a0<\/p>\n<p>En \u00a0estricto \u00a0sentido, \u00a0la \u00a0correcci\u00f3n de la \u00a0irregularidad, \u00a0que implicar\u00eda la repetici\u00f3n del juicio o, por lo menos, de la \u00a0pr\u00e1ctica \u00a0de \u00a0esta \u00a0prueba \u00a0para \u00a0salvar \u00a0a \u00a0\u201crajatabla\u201d \u00a0el \u00a0principio \u00a0de \u00a0inmediaci\u00f3n, \u00a0comportar\u00eda \u00a0un \u00a0da\u00f1o mayor al que se pretende solucionar, pues \u00a0se \u00a0someter\u00eda \u00a0al \u00a0ofendido \u00a0a \u00a0una \u00a0nueva \u00a0victimizaci\u00f3n \u00a0y, \u00a0en ese sentido, \u00a0estar\u00eda \u00a0afectando \u00a0el \u00a0inter\u00e9s \u00a0superior \u00a0del ni\u00f1o, pues seg\u00fan el principio \u00a0pro infans, en eventos donde \u00a0resultan \u00a0contrapuestas \u00a0las prerrogativas, deber\u00e1 optarse por la soluci\u00f3n que \u00a0otorgue m\u00e1s garant\u00edas a los derechos de los menores de edad. \u00a0\u00a0<\/p>\n<p>El art\u00edculo 193, numeral 7\u00ba, del C\u00f3digo de \u00a0la \u00a0Infancia \u00a0y \u00a0la \u00a0Adolescencia, \u00a0consagra \u00a0que \u00a0los \u00a0procesos \u00a0por \u00a0conductas \u00a0punibles, \u00a0donde \u00a0la \u00a0v\u00edctima \u00a0haya \u00a0sido \u00a0un \u00a0menor \u00a0de \u00a0edad, las autoridades \u00a0judiciales \u00a0no \u00a0le \u00a0deben \u00a0generar \u00a0da\u00f1os \u00a0adicionales, conforme a la sentencia \u00a0T-205 de 2011. \u00a0\u00a0<\/p>\n<p>En \u00a0ese \u00a0sentido, la Constituci\u00f3n Nacional y \u00a0los \u00a0principios \u00a0rectores \u00a0del \u00a0proceso penal acusatorio permiten, sin violar el \u00a0principio \u00a0de \u00a0inmediaci\u00f3n, \u00a0recurrir \u00a0a \u00a0la \u00a0apreciaci\u00f3n \u00a0de \u00a0la prueba de la \u00a0declaraci\u00f3n \u00a0del \u00a0ni\u00f1o \u00a0mediante \u00a0la \u00a0observaci\u00f3n \u00a0y escucha detallada de los \u00a0registros tenidos para el efecto. \u00a0\u00a0<\/p>\n<p>Acorde \u00a0 con \u00a0 las \u00a0especiales \u00a0condiciones \u00a0psicol\u00f3gicas, \u00a0sociales \u00a0y habilidades cognitivas del deponente, debe valorarse \u00a0su \u00a0 relato \u00a0 y \u00a0 escuch\u00e1rsele \u00a0 en \u00a0 los \u00a0 puntos \u00a0 en \u00a0 los \u00a0 que \u00a0a \u00a0\u00e9l \u00a0le \u00a0interesa. \u00a0\u00a0<\/p>\n<p>A \u00a0tal \u00a0respecto, \u00a0no \u00a0solo \u00a0el C\u00f3digo de la \u00a0Infancia \u00a0y \u00a0la \u00a0Adolescencia, \u00a0sino el art\u00edculo 12 de la Convenci\u00f3n sobre los \u00a0derechos \u00a0del \u00a0ni\u00f1o, \u00a0numerales \u00a01\u00ba \u00a0y \u00a02\u00ba, \u00a0se\u00f1ala \u00a0esta \u00a0obligaci\u00f3n en la \u00a0instrucci\u00f3n y juzgamiento. \u00a0\u00a0<\/p>\n<p>Adicionalmente, apunta que la defensa retom\u00f3 \u00a0los \u00a0argumentos \u00a0de \u00a0la \u00a0juez \u00a0de \u00a0primera \u00a0instancia, \u00a0con miras a se\u00f1alar las \u00a0inconsistencias \u00a0de \u00a0las \u00a0declaraciones dadas por el ofendido ante la psic\u00f3loga \u00a0en \u00a0el \u00a0juicio \u00a0oral \u00a0y ante su madre, y as\u00ed generar dudas insalvables sobre la \u00a0existencia de los actos imputados. \u00a0\u00a0<\/p>\n<p>No \u00a0obstante, \u00a0en las diversas intervenciones \u00a0del \u00a0menor, \u00a0lo dicho a su progenitora, a la psic\u00f3loga y en el juicio oral, hay \u00a0un \u00a0punto \u00a0que \u00a0resulta invariable y, por tanto, irrefutable, cre\u00edble, y es que \u00a0la \u00a0procesada \u00a0manipul\u00f3 los \u00f3rganos genitales del infante y lo oblig\u00f3 a tocar \u00a0los genitales de ella. \u00a0\u00a0<\/p>\n<p>El \u00a0relato \u00a0que \u00a0M.A.L.O dio al m\u00e9dico, a la \u00a0psic\u00f3loga \u00a0y \u00a0a la madre, puede presentar inconsistencias sobre fechas, n\u00famero \u00a0de \u00a0veces \u00a0y \u00a0lugar \u00a0de \u00a0ocurrencia, \u00a0pero \u00a0en \u00a0lo \u00a0sustancial \u00a0no \u00a0hay \u00a0duda ni \u00a0ambig\u00fcedad. \u00a0Siempre \u00a0fue \u00a0uniforme \u00a0al \u00a0sostener d\u00f3nde ocurrieron los hechos, \u00a0qui\u00e9n los ejecut\u00f3 y a qu\u00e9 tipo de vej\u00e1menes fue sometido. \u00a0\u00a0<\/p>\n<p>En \u00a0 ese \u00a0 sentido, \u00a0 si \u00a0 el \u00a0Ad \u00a0quem \u00a0hubiese \u00a0tenido \u00a0en \u00a0cuenta \u00a0la \u00a0declaraci\u00f3n \u00a0del \u00a0ni\u00f1o \u00a0en \u00a0el \u00a0juicio \u00a0oral, \u00a0habr\u00eda \u00a0arribado \u00a0a \u00a0la \u00a0misma \u00a0conclusi\u00f3n \u00a0 a \u00a0 la \u00a0 que \u00a0 lleg\u00f3, \u00a0en \u00a0grado \u00a0de \u00a0certeza, \u00a0en \u00a0cuanto \u00a0a \u00a0la \u00a0responsabilidad \u00a0penal \u00a0de \u00a0la acusada frente a los actos lascivos infringidos a \u00a0la v\u00edctima. \u00a0\u00a0<\/p>\n<p>Concluye, \u00a0de un lado, que el cargo formulado \u00a0en \u00a0la \u00a0demanda no est\u00e1 llamado a prosperar y, de otro, que no hay un asunto de \u00a0quebranto \u00a0trascendental \u00a0de la efectividad material ni a las garant\u00edas debidas \u00a0a \u00a0las \u00a0partes \u00a0que intervienen en la actuaci\u00f3n penal, que amerite el ejercicio \u00a0de la facultad discrecional de la Corte. \u00a0\u00a0<\/p>\n<p>4. Representante de la v\u00edctima. En \u00a0similares \u00a0t\u00e9rminos \u00a0se \u00a0pronunci\u00f3 \u00a0el letrado y aduj\u00f3 que el \u00a0Tribunal \u00a0jam\u00e1s incurri\u00f3 en error, sino que apreci\u00f3 bajo la sana cr\u00edtica los \u00a0relatos \u00a0del \u00a0menor \u00a0ante \u00a0la \u00a0psic\u00f3loga de la Sijin, de la madre y del m\u00e9dico \u00a0forense, \u00a0para \u00a0concluir, \u00a0sin \u00a0duda, \u00a0en los tocamientos de los que hab\u00eda sido \u00a0v\u00edctima por parte de NATALY DUARTE. \u00a0\u00a0<\/p>\n<p>Considera \u00a0que \u00a0el demandante pretende seguir \u00a0reprochando \u00a0las \u00a0pruebas practicadas en juicio, por lo cual no se debe casar la \u00a0sentencia. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0<\/p>\n<p>La \u00a0Sala \u00a0se \u00a0pronunciar\u00e1, \u00a0en primer lugar, \u00a0sobre \u00a0la \u00a0propuesta \u00a0casacional \u00a0del \u00a0impugnante, \u00a0y \u00a0luego abordar\u00e1 los temas \u00a0aludidos \u00a0 por \u00a0 los \u00a0 representantes \u00a0 de \u00a0 la \u00a0 Fiscal\u00eda \u00a0 y \u00a0 el \u00a0Ministerio \u00a0P\u00fablico. \u00a0\u00a0<\/p>\n<p>1. \u00a0Importa \u00a0se\u00f1alar \u00a0ante todo que, como se \u00a0anunci\u00f3 \u00a0en \u00a0el auto admisorio, las exigencias previstas en el art\u00edculo 184 de \u00a0la \u00a0Ley \u00a0906 \u00a0de \u00a02004 \u00a0fueron \u00a0desatendidas \u00a0a \u00a0cabalidad en la confecci\u00f3n del \u00a0libelo, \u00a0por \u00a0cuanto \u00a0el \u00a0impugnante \u00a0se \u00a0sustrajo de acreditar objetivamente la \u00a0ocurrencia \u00a0 de \u00a0 alg\u00fan \u00a0 yerro \u00a0judicial \u00a0y \u00a0su \u00a0incidencia \u00a0en \u00a0la \u00a0decisi\u00f3n \u00a0objetada. \u00a0\u00a0<\/p>\n<p>Lo \u00a0 anterior \u00a0 es \u00a0 as\u00ed, \u00a0 porque \u00a0en \u00a0su \u00a0argumentaci\u00f3n \u00a0no atin\u00f3 a demostrar la ocurrencia del error de hecho por falso \u00a0raciocinio, \u00a0haciendo \u00a0ver \u00a0que \u00a0el Tribunal, al momento de apreciar la prueba o \u00a0pruebas \u00a0objeto \u00a0del disenso, se apart\u00f3 de los principios que gobiernan la sana \u00a0cr\u00edtica. \u00a0\u00a0<\/p>\n<p>En \u00a0otras \u00a0palabras, no precis\u00f3, como era su \u00a0deber, \u00a0qu\u00e9 \u00a0dicen \u00a0los \u00a0medios \u00a0de \u00a0convicci\u00f3n, \u00a0qu\u00e9 \u00a0infiri\u00f3 \u00a0de \u00a0ellos el \u00a0sentenciador, \u00a0cu\u00e1l \u00a0el \u00a0m\u00e9rito persuasivo que les asign\u00f3, y tampoco se\u00f1al\u00f3 \u00a0el \u00a0postulado \u00a0l\u00f3gico, \u00a0la \u00a0ley \u00a0cient\u00edfica \u00a0o \u00a0la \u00a0m\u00e1xima \u00a0de la experiencia \u00a0supuestamente \u00a0desconocida \u00a0y \u00a0su \u00a0trascendencia en la declaraci\u00f3n de justicia. \u00a0Igualmente, \u00a0omiti\u00f3 \u00a0ense\u00f1ar \u00a0la \u00a0manera \u00a0como \u00a0se \u00a0debe \u00a0corregir el supuesto \u00a0dislate, \u00a0haciendo ver el efecto favorable de la enmienda en la situaci\u00f3n de la \u00a0procesada. \u00a0\u00a0<\/p>\n<p>En \u00a0realidad, \u00a0aspira \u00a0el \u00a0demandante \u00a0que se \u00a0mantenga \u00a0la \u00a0decisi\u00f3n \u00a0absolutoria de primera instancia, acudiendo para ello a \u00a0una \u00a0cr\u00edtica \u00a0abiertamente \u00a0incompatible \u00a0con \u00a0la especie de censura anunciada, \u00a0pues \u00a0con \u00a0ese \u00a0objetivo, procedi\u00f3 a destacar las imprecisiones del agredido en \u00a0sus \u00a0relatos, \u00a0a \u00a0sugerir \u00a0c\u00f3mo \u00a0se \u00a0debi\u00f3 valorar el hecho de las rec\u00edprocas \u00a0denuncias \u00a0formuladas por los padres del infante y las razones por las cuales se \u00a0debe \u00a0acoger el dictamen rendido por la psic\u00f3loga de la Defensor\u00eda del Pueblo, \u00a0en \u00a0cuanto \u00a0concluy\u00f3 que \u201cla credibilidad del menor \u00a0es \u00a0 \u00a0indeterminada\u201d. \u00a0\u00a0<\/p>\n<p>Y \u00a0aun cuando afirm\u00f3 desconocidas las reglas \u00a0de \u00a0la \u00a0l\u00f3gica \u00a0y \u00a0de \u00a0la \u00a0experiencia, \u00a0no \u00a0hizo \u00a0ver \u00a0tales \u00a0desatinos en las \u00a0deducciones \u00a0del \u00a0Ad \u00a0quem, \u00a0pues \u00a0ni \u00a0siquiera \u00a0se \u00a0refiri\u00f3 \u00a0puntualmente \u00a0a \u00a0los \u00a0juicios \u00a0valorativos que \u00a0condujeron \u00a0 \u00a0a \u00a0 \u00a0revocar \u00a0 \u00a0la \u00a0 \u00a0absoluci\u00f3n \u00a0 \u00a0e \u00a0 impartir \u00a0 sentencia \u00a0 de \u00a0condena. \u00a0\u00a0<\/p>\n<p>Entonces, \u00a0como el vicio anunciado no pasa de \u00a0ser \u00a0una \u00a0apreciaci\u00f3n \u00a0subjetiva \u00a0del \u00a0censor, \u00a0la \u00a0Sala \u00a0opt\u00f3 por superar los \u00a0defectos \u00a0del \u00a0libelo \u00a0en \u00a0aras \u00a0de \u00a0examinar \u00a0el \u00a0fondo del asunto, con miras a \u00a0verificar la posible violaci\u00f3n de garant\u00edas fundamentales. \u00a0\u00a0<\/p>\n<p>2. En orden a precisar el objeto de an\u00e1lisis, \u00a0es \u00a0obligado \u00a0destacar que el Tribunal, en su decisi\u00f3n, opt\u00f3 por no valorar el \u00a0testimonio \u00a0del \u00a0menor \u00a0afectado al advertir que su relato lo presenci\u00f3 un juez \u00a0distinto \u00a0al que anunci\u00f3 el sentido del fallo y lo redact\u00f3, refiriendo que esa \u00a0situaci\u00f3n \u00a0no obliga a la repetici\u00f3n del juicio oral en cuanto se apoyar\u00eda en \u00a0la \u00a0restante \u00a0prueba \u00a0incorporada \u00a0al \u00a0proceso \u00a0con \u00a0apego \u00a0a \u00a0los principios de \u00a0concentraci\u00f3n, \u00a0 \u00a0publicidad, \u00a0 \u00a0inmediaci\u00f3n \u00a0 \u00a0y \u00a0 \u00a0permanencia \u00a0 \u00a0del \u00a0 juez \u00a0natural. \u00a0\u00a0<\/p>\n<p>Consecuente con ello, apunt\u00f3 que \u201c[l]a \u00a0no \u00a0apreciaci\u00f3n \u00a0de la declaraci\u00f3n de M.A.L.O. no genera \u00a0afectaci\u00f3n \u00a0 de \u00a0 los \u00a0 derechos \u00a0 y \u00a0 garant\u00edas \u00a0fundamentales\u201d9, \u00a0consideraci\u00f3n \u00a0frente \u00a0a \u00a0la \u00a0cual \u00a0las \u00a0partes \u00a0intervinientes en sede de este \u00a0recurso extraordinario, hicieron manifiesta su protesta. \u00a0\u00a0<\/p>\n<p>En criterio del se\u00f1or Fiscal Delegado, pese a \u00a0que \u00a0no \u00a0se \u00a0requiere la repetici\u00f3n del juicio oral para escuchar el testimonio \u00a0del \u00a0infante, \u00a0su \u00a0declaraci\u00f3n debi\u00f3 ser objeto de valoraci\u00f3n por tratarse de \u00a0la v\u00edctima del delito. \u00a0\u00a0<\/p>\n<p>A \u00a0juicio \u00a0de la representante del Ministerio \u00a0P\u00fablico, \u00a0es \u00a0posible \u00a0que, sin violar el principio de inmediaci\u00f3n, se aprecie \u00a0la \u00a0declaraci\u00f3n \u00a0del \u00a0ni\u00f1o \u00a0acudiendo a la observaci\u00f3n y escucha detallada de \u00a0los registros tenidos para el efecto. \u00a0\u00a0<\/p>\n<p>2.1. \u00a0 El \u00a0 an\u00e1lisis \u00a0 de \u00a0las \u00a0anteriores \u00a0reflexiones \u00a0 \u00a0obliga \u00a0 a \u00a0 recordar, \u00a0 ab \u00a0 initio, \u00a0que \u00a0desde \u00a0la \u00a0entrada \u00a0en \u00a0vigencia de la Ley 906 de \u00a02004, \u00a0 \u00a0 la \u00a0 \u00a0jurisprudencia \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0Sala10 \u00a0ha reconocido la importancia \u00a0de \u00a0los \u00a0principios de inmediaci\u00f3n, concentraci\u00f3n y juez natural en el sistema \u00a0penal \u00a0acusatorio, \u00a0en \u00a0cuanto \u00a0propenden \u00a0por \u00a0la \u00a0permanencia \u00a0del \u00a0juez en el \u00a0desarrollo \u00a0del \u00a0debate oral, con miras a que se forme una idea clara de todo lo \u00a0ocurrido \u00a0y, luego de valorar el caudal probatorio, anuncie el sentido del fallo \u00a0y profiera la decisi\u00f3n. \u00a0\u00a0<\/p>\n<p>Es \u00a0por \u00a0ello \u00a0que \u00a0el \u00a0art\u00edculo \u00a0454 de esa \u00a0normativa, \u00a0prev\u00e9 \u00a0en \u00a0su \u00a0inciso \u00a03\u00ba la repetici\u00f3n del juicio oral cuando se \u00a0deba \u00a0suspender \u00a0la \u00a0audiencia por un lapso temporal que incida en la memoria de \u00a0lo \u00a0ocurrido, \u00a0en \u00a0especial \u00a0frente a las pruebas practicadas, as\u00ed se trate del \u00a0mismo \u00a0 funcionario \u00a0 que \u00a0 ha \u00a0tenido \u00a0contacto \u00a0directo \u00a0con \u00a0ese \u00a0recaudo, \u00a0o \u00a0cuando \u00a0 se \u00a0 deba \u00a0 cambiar \u00a0 de \u00a0 juez. \u00a0\u00a0<\/p>\n<p>A \u00a0tono con estas directrices, tambi\u00e9n se ha \u00a0enfatizado \u00a0que \u00a0conforme \u00a0al art\u00edculo 19 de la Ley 906 de 2004, el concepto de \u00a0juez \u00a0natural \u00a0hace \u00a0referencia \u00a0a \u00a0la \u00a0persona, al titular del despacho y no al \u00a0cargo11. \u00a0\u00a0<\/p>\n<p>2.2. \u00a0Sin \u00a0embargo, resulta obligado advertir \u00a0que \u00a0 \u00a0 \u00a0 en \u00a0 \u00a0 \u00a0 reciente \u00a0 \u00a0 \u00a0pronunciamiento12, la Sala ampli\u00f3 la anterior \u00a0l\u00ednea \u00a0jurisprudencial, \u00a0en \u00a0el \u00a0sentido \u00a0de \u00a0precisar \u00a0que \u00a0los \u00a0principios de \u00a0inmediaci\u00f3n y concentraci\u00f3n \u00a0no son absolutos, pues si \u00a0bien \u00a0forman \u00a0parte \u00a0sustancial \u00a0del \u00a0sistema \u00a0penal \u00a0acusatorio, \u00a0no es posible \u00a0mantener \u00a0una \u00a0regla r\u00edgida de repetici\u00f3n del juicio, cada vez que se susciten \u00a0cambios \u00a0en \u00a0la \u00a0persona \u00a0del \u00a0juez \u00a0presente en la pr\u00e1ctica de las pruebas que \u00a0soportan \u00a0 la \u00a0sentencia, \u00a0sino \u00a0que \u00a0ser\u00e1 \u00a0necesario \u00a0examinar \u00a0cada \u00a0caso \u00a0en \u00a0particular \u00a0en \u00a0orden \u00a0a \u00a0ponderar los efectos del \u00e1mbito de protecci\u00f3n de los \u00a0principios \u00a0procesales, \u00a0para \u00a0evitar \u00a0la \u00a0afectaci\u00f3n \u00a0de \u00a0garant\u00edas \u00a0de mayor \u00a0cobertura \u00a0o \u00a0decisiones \u00a0desconocedoras \u00a0de \u00a0los \u00a0derechos \u00a0de \u00a0las v\u00edctimas o \u00a0terceros involucrados en la actuaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Para \u00a0ese efecto, apreci\u00f3 necesario recabar, \u00a0con \u00a0apoyo en la jurisprudencia constitucional, que el funcionario judicial debe \u00a0respetar \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 hacer \u00a0 \u00a0 valer \u00a0 \u00a0 el \u00a0 \u00a0 principio \u00a0 \u00a0 de \u00a0 \u00a0 celeridad \u00a0como componente del derecho de \u00a0acceso a la administraci\u00f3n de justicia. Tambi\u00e9n \u00a0 \u00a0hizo \u00a0 \u00a0ver \u00a0 \u00a0que \u00a0 \u00a0el \u00a0 postulado \u00a0 de \u00a0 inmediaci\u00f3n no \u00a0hace \u00a0parte \u00a0esencial \u00a0de \u00a0un \u00a0debido \u00a0proceso \u00a0en \u00a0general \u00a0y, \u00a0de \u00a0contera, su \u00a0desconocimiento \u00a0solo \u00a0opera \u00a0frente a casos tramitados bajo la Ley 906 de 2004, \u00a0normativa \u00a0 \u00a0que \u00a0 \u00a0a \u00a0 su \u00a0 vez \u00a0 contempla \u00a0 diversas \u00a0 limitaciones \u00a0 en \u00a0 su \u00a0aplicaci\u00f3n. \u00a0\u00a0<\/p>\n<p>As\u00ed, \u00a0tras \u00a0examinar \u00a0esa \u00a0tem\u00e1tica \u00a0con la \u00a0debida profundidad, esta Corporaci\u00f3n concluy\u00f3: \u00a0\u00a0<\/p>\n<p>1. \u00a0El \u00a0principio \u00a0de inmediaci\u00f3n tiene una \u00a0connotaci\u00f3n \u00a0eminentemente \u00a0procesal, \u00a0definida \u00a0por \u00a0el \u00a0tipo de procedimiento \u00a0adoptado en determinado momento hist\u00f3rico. \u00a0\u00a0<\/p>\n<p>2. El principio de inmediaci\u00f3n no hace parte \u00a0del \u00a0 n\u00facleo \u00a0 fuerte \u00a0 del \u00a0 debido \u00a0proceso \u00a0que \u00a0en \u00a0Colombia \u00a0se \u00a0instituye \u00a0constitucionalmente \u00a0en \u00a0el \u00a0art\u00edculo \u00a029 \u00a0de \u00a0la \u00a0Carta \u00a0Pol\u00edtica, \u00a0aunque ya \u00a0instituido \u00a0el \u00a0tr\u00e1mite \u00a0consagrado \u00a0en \u00a0el \u00a0art\u00edculo \u00a0250 \u00a0de \u00a0la \u00a0misma, \u00a0su \u00a0eliminaci\u00f3n \u00a0o afectaci\u00f3n del n\u00facleo b\u00e1sico s\u00ed conduce a estimar violado el \u00a0debido \u00a0 \u00a0 proceso \u00a0 \u00a0 y, \u00a0 \u00a0 consecuencialmente, \u00a0 \u00a0los \u00a0 \u00a0dictados \u00a0 \u00a0de \u00a0 \u00a0la \u00a0Constituci\u00f3n. \u00a0\u00a0<\/p>\n<p>3. El Pacto Internacional de Derechos Civiles \u00a0y \u00a0Pol\u00edticos, \u00a0la \u00a0Declaraci\u00f3n \u00a0Universal \u00a0de \u00a0los \u00a0Derechos \u00a0del \u00a0Hombre y La \u00a0Convenci\u00f3n \u00a0Americana \u00a0de Derechos Humanos, referentes ineludibles para nuestro \u00a0pa\u00eds, \u00a0no \u00a0consideran \u00a0el principio de inmediaci\u00f3n como uno basilar u obligado \u00a0de preservar por los Estados parte. \u00a0\u00a0<\/p>\n<p>4. \u00a0 En \u00a0 contrario, \u00a0 tanto \u00a0 el \u00a0 Pacto \u00a0Internacional, \u00a0como la Convenci\u00f3n Americana, demandan obligatorio permitir del \u00a0condenado impugnar la sentencia ante un tribunal superior. \u00a0\u00a0<\/p>\n<p>5. \u00a0Esa \u00a0exigencia \u00a0se \u00a0reproduce \u00a0en \u00a0el \u00a0art\u00edculo \u00a029 \u00a0de \u00a0la \u00a0Carta \u00a0Pol\u00edtica \u00a0colombiana y fue extendida por la Corte \u00a0Constitucional a los fallos absolutorios. \u00a0\u00a0<\/p>\n<p>6. \u00a0Tanto \u00a0la \u00a0posibilidad \u00a0de impugnar los \u00a0fallos \u00a0ante otra instancia, como los institutos de prueba anticipada, la prueba \u00a0de \u00a0referencia y el recurso extraordinario de casaci\u00f3n, representan limitaci\u00f3n \u00a0al principio de inmediaci\u00f3n. \u00a0\u00a0<\/p>\n<p>7. \u00a0El principio de inmediaci\u00f3n debe ceder \u00a0ante \u00a0otros derechos fundamentales o de m\u00e1s peso y, en consecuencia, la nulidad \u00a0de \u00a0la audiencia de juicio oral cuando las pruebas no fueron practicadas ante el \u00a0funcionario \u00a0encargado \u00a0de emitir el sentido del fallo o \u00e9ste, s\u00f3lo opera como \u00a0mecanismo \u00a0excepcional\u00edsimo \u00a0cuando se advierta que esa circunstancia caus\u00f3 un \u00a0da\u00f1o grave. \u00a0\u00a0<\/p>\n<p>Bajo \u00a0esas \u00a0directrices, \u00a0la \u00a0Sala consider\u00f3 \u00a0forzoso \u00a0expandir \u00a0la \u00a0tesis \u00a0que \u00a0se \u00a0ven\u00eda \u00a0sosteniendo, al evidenciar que el \u00a0principio \u00a0 de \u00a0 inmediaci\u00f3n \u00a0 \u201cno \u00a0 comporta \u00a0la \u00a0naturaleza \u00a0 y \u00a0 efectos \u00a0 superlativos \u00a0que \u00a0se \u00a0estimaron \u00a0en \u00a0las \u00a0decisiones \u00a0jurisprudenciales \u00a0ampliamente \u00a0rese\u00f1adas en precedencia y, en consecuencia, su \u00a0limitaci\u00f3n \u00a0o \u00a0afectaci\u00f3n \u00a0no \u00a0necesariamente \u00a0implica \u00a0que \u00a0deba \u00a0acudirse al \u00a0remedio extremo de la nulidad\u201d. \u00a0\u00a0<\/p>\n<p>A \u00a0continuaci\u00f3n, \u00a0plasm\u00f3 \u00a0los \u00a0siguientes \u00a0derroteros: \u00a0\u00a0<\/p>\n<p>La \u00a0Sala, visto que el principio en estudio \u00a0debe \u00a0balancearse con otros de igual o superior cariz protectivo, entre ellos el \u00a0de \u00a0acceso \u00a0a \u00a0la justicia en su componente de celeridad, junto con los derechos \u00a0de \u00a0los \u00a0menores, las v\u00edctimas y testigos, ha de advertir que no necesariamente \u00a0debe \u00a0propenderse \u00a0por \u00a0el remedio extremo de la nulidad en los casos en los que \u00a0el \u00a0funcionario \u00a0encargado \u00a0de \u00a0emitir \u00a0el \u00a0fallo estuvo ausente de la pr\u00e1ctica \u00a0probatoria fuerte. \u00a0\u00a0<\/p>\n<p>Ello, \u00a0se \u00a0resalta, \u00a0porque en s\u00ed mismo el \u00a0principio \u00a0de \u00a0inmediaci\u00f3n \u00a0no \u00a0representa \u00a0un \u00a0valor \u00a0constitucional, \u00a0legal o \u00a0procesal \u00a0obligado de respetar de manera absoluta, superior, y ni siquiera de la \u00a0misma jerarqu\u00eda, a otros inmanentes que deben privilegiarse. \u00a0\u00a0<\/p>\n<p>Comparte \u00a0la Corte Suprema de Justicia, con \u00a0su \u00a0par Constitucional, que en raz\u00f3n a esa naturaleza intr\u00ednseca del principio \u00a0de \u00a0inmediaci\u00f3n, \u00a0su \u00a0afectaci\u00f3n \u00a0o limitaci\u00f3n no debe conducir a la nulidad, \u00a0que \u00a0 apenas \u00a0 puede \u00a0 decretarse \u00a0en \u00a0circunstancias \u00a0particular\u00edsimas \u00a0y \u00a0muy \u00a0excepcionales \u00a0de da\u00f1o grave demostrado a otros distintos derechos de raigambre \u00a0fundamental. \u00a0\u00a0<\/p>\n<p>De esta manera, nunca la sola afirmaci\u00f3n de \u00a0que \u00a0 \u00a0 el \u00a0 \u00a0 juez \u00a0 \u00a0 encargado \u00a0 \u00a0de \u00a0 \u00a0emitir \u00a0 \u00a0el \u00a0 \u00a0fallo \u00a0 \u00a0\u2013o \u00a0su \u00a0sentido- \u00a0es distinto de aquel \u00a0encargado \u00a0de \u00a0presenciar la pr\u00e1ctica probatoria trascendente, puede conducir a \u00a0la \u00a0anulaci\u00f3n \u00a0del \u00a0juicio \u00a0oral, \u00a0consecuencia \u00a0que, \u00a0de \u00a0solicitarse, \u00a0obliga \u00a0demostrar \u00a0 \u00a0 grave \u00a0 \u00a0afectaci\u00f3n \u00a0 \u00a0de \u00a0 \u00a0otros \u00a0 \u00a0derechos \u00a0 \u00a0o \u00a0 \u00a0principios \u00a0fundamentales. \u00a0\u00a0<\/p>\n<p>Es \u00a0que, para el operador judicial debe ser \u00a0materia \u00a0obligada \u00a0de \u00a0examen, \u00a0cuando \u00a0se \u00a0presente la circunstancia analizada, \u00a0tanto \u00a0lo \u00a0correspondiente \u00a0a \u00a0las razones que motivaron ese cambio de fallador, \u00a0como \u00a0los \u00a0derechos \u00a0que \u00a0en \u00a0concreto \u00a0pueden \u00a0ser \u00a0afectados \u00a0si se dispone la \u00a0nulidad. \u00a0\u00a0<\/p>\n<p>Entonces, \u00a0para \u00a0ir precisando el punto con \u00a0los \u00a0t\u00f3picos \u00a0que \u00a0al d\u00eda de hoy se observan decantados, si la repetici\u00f3n del \u00a0juicio \u00a0implica afectar de manera importante o grave los derechos de los menores \u00a0\u2013v\u00edctimas \u00a0o \u00a0testigos \u00a0trascendentales- \u00a0; \u00a0o \u00a0de \u00a0las \u00a0mujeres \u00a0v\u00edctimas \u00a0de \u00a0delitos \u00a0sexuales \u00a0(que \u00a0obligadas \u00a0 a \u00a0recordar \u00a0el \u00a0episodio \u00a0vejatorio \u00a0pueden \u00a0ser \u00a0objeto \u00a0de \u00a0doble \u00a0victimizaci\u00f3n \u00a0o \u00a0sufrir da\u00f1os sicol\u00f3gicos); o si corren peligro los testigos \u00a0o \u00a0v\u00edctimas, \u00a0en \u00a0atenci\u00f3n \u00a0a \u00a0amenazas o temores fundados de retaliaci\u00f3n; el \u00a0juez \u00a0debe \u00a0ponderar \u00a0los derechos en juego para proteger a estas personas y, en \u00a0consecuencia, \u00a0mientras \u00a0no \u00a0existan \u00a0razones \u00a0de mayor peso, diferentes a la de \u00a0tutelar \u00a0de \u00a0forma \u00a0irrestricta \u00a0el \u00a0principio \u00a0de \u00a0inmediaci\u00f3n, \u00a0est\u00e1 \u00a0en \u00a0la \u00a0obligaci\u00f3n de morigerarlo y evitar la invalidez del juicio. \u00a0\u00a0<\/p>\n<p>Pero, adem\u00e1s, la definici\u00f3n de cu\u00e1l debe \u00a0ser \u00a0la \u00a0soluci\u00f3n \u00a0tambi\u00e9n \u00a0debe pasar por apreciar cu\u00e1les fueron las razones \u00a0que obligaron el cambio de funcionario. \u00a0\u00a0<\/p>\n<p>De \u00a0esta manera, para citar apenas por v\u00eda \u00a0enunciativa \u00a0algunos \u00a0temas \u00a0puntuales, \u00a0si \u00a0son \u00a0motivos de fuerza mayor o caso \u00a0fortuito \u00a0los \u00a0que demandan el cambio de juez, d\u00edgase la licencia por embarazo, \u00a0la \u00a0muerte \u00a0o \u00a0enfermedad \u00a0impeditiva \u00a0que se prolonga en el tiempo, la sanci\u00f3n \u00a0disciplinaria \u00a0o \u00a0medida restrictiva personal de car\u00e1cter penal que se impongan \u00a0al \u00a0titular \u00a0del \u00a0despacho, las calamidades que obliguen la dejaci\u00f3n prolongada \u00a0de \u00a0la \u00a0funci\u00f3n, \u00a0siempre \u00a0ser\u00e1 \u00a0necesario \u00a0proteger \u00a0lo \u00a0actuado \u00a0evitando la \u00a0nulidad, \u00a0dado \u00a0que \u00a0esas \u00a0son \u00a0situaciones \u00a0que \u00a0se \u00a0salen \u00a0de \u00a0las manos de la \u00a0judicatura \u00a0o \u00a0su \u00a0administraci\u00f3n, al punto que no pueden preverse o eliminarse \u00a0en sus efectos inmediatos. \u00a0\u00a0<\/p>\n<p>Ahora, si el cambio de funcionario obedece a \u00a0una \u00a0situaci\u00f3n \u00a0administrativa \u00a0normal \u00a0o previsible, ya no es posible acudir a \u00a0esos \u00a0factores \u00a0ingobernables para soportar mantener inc\u00f3lume el proceso, pues, \u00a0aqu\u00ed \u00a0s\u00ed \u00a0refulge \u00a0en \u00a0toda su dimensi\u00f3n el principio de inmediaci\u00f3n, que no \u00a0puede \u00a0ser \u00a0desnaturalizado \u00a0s\u00f3lo en atenci\u00f3n a circunstancias particulares de \u00a0inter\u00e9s apenas para el funcionario. \u00a0\u00a0<\/p>\n<p>En \u00a0estos \u00a0casos, sigue invariable el deber \u00a0del \u00a0juez \u00a0de adelantar el juicio desde su inicio hasta la cabal terminaci\u00f3n; y \u00a0de \u00a0los \u00a0nominadores, \u00a0de \u00a0hacer \u00a0respetar \u00a0esa \u00a0obligaci\u00f3n, \u00a0como \u00a0as\u00ed lo han \u00a0se\u00f1alado la Corte Constitucional y esta Corporaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Para \u00a0resumir, \u00a0la \u00a0nulidad \u00a0s\u00f3lo \u00a0puede \u00a0decretarse \u00a0 excepcionalmente, \u00a0 cuando \u00a0 se \u00a0 cumplan \u00a0 (en \u00a0 conjunci\u00f3n) \u00a0dos \u00a0presupuestos: \u00a0(i) \u00a0que no se afecten de forma importante o grave otros derechos \u00a0fundamentales; \u00a0(ii) \u00a0que \u00a0el \u00a0cambio \u00a0de \u00a0funcionario no obedezca a situaciones \u00a0ingobernables para el funcionario o la administraci\u00f3n.\u00a0 \u00a0\u00a0<\/p>\n<p>Debe \u00a0precisar la Corte que la decisi\u00f3n en \u00a0ciernes \u00a0no \u00a0significa \u00a0sacrificar \u00a0absolutamente, \u00a0o mejor, eliminar el n\u00facleo \u00a0central \u00a0del principio de inmediaci\u00f3n, en tanto, no puede desconocerse c\u00f3mo al \u00a0d\u00eda \u00a0de \u00a0hoy \u00a0los adelantos tecnol\u00f3gicos, facultan remplazar con una fidelidad \u00a0bastante \u00a0 \u00a0 aceptable \u00a0 \u00a0la \u00a0 \u00a0verificaci\u00f3n \u00a0 \u00a0in \u00a0situ \u00a0 que \u00a0 realiza \u00a0 el \u00a0 juez \u00a0 dentro \u00a0 de \u00a0 la \u00a0audiencia. \u00a0\u00a0<\/p>\n<p>Y, entonces, si los registros de lo sucedido \u00a0en \u00a0la \u00a0pr\u00e1ctica \u00a0probatoria permiten esa auscultaci\u00f3n directa del funcionario \u00a0encargado \u00a0de \u00a0emitir \u00a0el \u00a0fallo, \u00a0sin \u00a0desnaturalizar el contenido esencial del \u00a0medio, \u00a0nada \u00a0obsta \u00a0para \u00a0que el examen se adelante por quien remplaz\u00f3 al juez \u00a0anterior. \u00a0\u00a0<\/p>\n<p>Desde \u00a0 luego, \u00a0 en \u00a0 todos \u00a0 los \u00a0casos, \u00a0independientemente \u00a0que \u00a0se afecten otros derechos de mayor calado o se trate de \u00a0una \u00a0situaci\u00f3n \u00a0obligada de sustituci\u00f3n del funcionario, si no existe registro \u00a0de \u00a0la \u00a0pr\u00e1ctica \u00a0probatoria \u00a0realizada \u00a0en \u00a0la \u00a0audiencia de juicio oral, o la \u00a0fidelidad \u00a0del mismo es tan precaria que impide verificar cabalmente lo ocurrido \u00a0con \u00a0las pruebas, es menester anular lo actuado y repetir el juicio a partir del \u00a0momento en que se inicia la presentaci\u00f3n de las pruebas. \u00a0\u00a0<\/p>\n<p>En contrario, si se cumpli\u00f3 cabalmente con \u00a0la \u00a0posibilidad \u00a0de \u00a0contradicci\u00f3n \u00a0y \u00a0confrontaci\u00f3n \u00a0probatoria \u00a0\u2013con \u00a0la obvia excepci\u00f3n de la prueba \u00a0de \u00a0referencia \u00a0y \u00a0su \u00a0eficacia \u00a0demostrativa \u00a0limitada-, \u00a0se \u00a0tomaron registros \u00a0fidedignos \u00a0que permitan del fallador examinar la prueba de forma adecuada, y si \u00a0adem\u00e1s \u00a0se entiende necesario proteger derechos fundamentales o se advierte que \u00a0la \u00a0sustituci\u00f3n del juez devino obligada, no es factible decretar la nulidad de \u00a0la \u00a0audiencia \u00a0de \u00a0juicio \u00a0oral \u00a0apenas \u00a0buscando \u00a0que se repitan las pruebas en \u00a0presencia del funcionario que proferir\u00e1 el fallo. \u00a0\u00a0<\/p>\n<p>En armon\u00eda con esa l\u00ednea de pensamiento, se \u00a0dijo \u00a0en el citado pronunciamiento, que cuando en el juicio se suscita cambio de \u00a0funcionario \u00a0 por \u00a0 otro \u00a0 con \u00a0 iguales \u00a0calidades \u00a0y \u00a0competencia \u00a0previamente \u00a0establecidas \u00a0en la ley, no se vulnera el principio de \u00a0juez \u00a0 natural, \u00a0porque \u00a0si \u00a0as\u00ed \u00a0fuera \u00a0proceder\u00eda \u00a0decretar \u00a0la \u00a0nulidad \u00a0en \u00a0todos los casos, sin ninguna verificaci\u00f3n adicional, \u00a0entre \u00a0otras razones, porque ese principio ostenta una jerarqu\u00eda superior al de \u00a0inmediaci\u00f3n \u00a0y, \u00a0por \u00a0tanto, \u00a0su \u00a0afectaci\u00f3n abarcar\u00eda un mayor \u00e1mbito de la \u00a0actuaci\u00f3n. \u00a0\u00a0<\/p>\n<p>2.3. \u00a0En \u00a0s\u00edntesis, \u00a0es \u00a0di\u00e1fano, \u00a0que \u00a0la \u00a0declaratoria \u00a0 de \u00a0 nulidad \u00a0 con \u00a0 miras \u00a0 a \u00a0 repetir \u00a0el \u00a0juicio \u00a0se \u00a0muestra \u00a0excepcional\u00edsima, \u00a0esto \u00a0es, cuando causa grave lesi\u00f3n a derechos o garant\u00edas \u00a0de \u00a0valor \u00a0superior, \u00a0no \u00a0siendo suficiente la sola desatenci\u00f3n al principio de \u00a0inmediaci\u00f3n \u00a0y \u00a0menos \u00a0a\u00fan \u00a0si en la actuaci\u00f3n se encuentran involucrados los \u00a0derechos \u00a0de \u00a0un \u00a0menor \u00a0de \u00a0edad, \u00a0bien se trate de la v\u00edctima o de un testigo \u00a0esencial. \u00a0\u00a0<\/p>\n<p>3. \u00a0En \u00a0un \u00a0asunto como el que se examina, la \u00a0decisi\u00f3n \u00a0 de \u00a0 no \u00a0repetir \u00a0el \u00a0juicio \u00a0debe \u00a0estar \u00a0soportada \u00a0en \u00a0la \u00a0previa \u00a0verificaci\u00f3n \u00a0de \u00a0las particulares circunstancias del caso, as\u00ed como del da\u00f1o \u00a0que \u00a0caus\u00f3 \u00a0la \u00a0pr\u00e1ctica \u00a0de \u00a0la \u00a0prueba \u00a0por \u00a0otro \u00a0funcionario. Superado ese \u00a0escollo, \u00a0se \u00a0hace necesario ponderar los derechos que pueden resultar afectados \u00a0si se optara por la nulidad. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0por \u00a0tratarse \u00a0del testimonio de un \u00a0menor \u00a0de \u00a0edad, \u00a0a \u00a0la \u00a0saz\u00f3n, \u00a0v\u00edctima \u00a0del delito, es ineludible atender al \u00a0principio \u00a0 \u00a0 de \u00a0 \u00a0 prevalencia \u00a0 \u00a0del \u00a0 \u00a0inter\u00e9s \u00a0superior, \u00a0seg\u00fan \u00a0el cual, la soluci\u00f3n que se adopte \u00a0debe \u00a0garantizar \u00a0el bienestar del infante y la plena satisfacci\u00f3n de todos sus \u00a0derechos, \u00a0tal como lo dispone el ordenamiento patrio13, \u00a0 \u00a0 \u00a0los \u00a0 \u00a0 \u00a0tratados \u00a0internacionales14, \u00a0 \u00a0 y \u00a0 \u00a0la \u00a0 \u00a0reiterada \u00a0jurisprudencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 constitucional15, \u00a0y \u00a0en virtud del principio \u00a0pro \u00a0infans, \u00a0es imperativo \u00a0aplicar \u00a0la medida que les otorgue mayores garant\u00edas, en aquellos eventos donde \u00a0resulten contrapuestas dos prerrogativas. \u00a0\u00a0<\/p>\n<p>Si \u00a0el \u00a0Ad \u00a0quem \u00a0hubiese \u00a0considerado \u00a0esas \u00a0directrices, \u00a0bien hubiese \u00a0podido \u00a0acudir \u00a0a \u00a0los \u00a0registros \u00a0contentivos \u00a0de \u00a0la \u00a0declaraci\u00f3n rendida por \u00a0M.A.L.O., \u00a0para \u00a0valorarla \u00a0en \u00a0conjunto con los dem\u00e1s elementos demostrativos, \u00a0m\u00e1xime \u00a0cuando la Corte Constitucional, en sentencia C-059 de 2010, al examinar \u00a0la \u00a0constitucionalidad \u00a0de \u00a0los art\u00edculos 454 de la Ley 906 de 2004 y 189 de la \u00a0Ley 1098 de 2006, hizo las siguientes advertencias: \u00a0\u00a0<\/p>\n<p>Por \u00a0supuesto \u00a0que \u00a0la interrupci\u00f3n de las \u00a0audiencias \u00a0de \u00a0juzgamiento \u00a0no \u00a0es \u00a0deseable en un sistema penal acusatorio, ni \u00a0debe \u00a0 convertirse \u00a0 en \u00a0 una \u00a0 pr\u00e1ctica \u00a0recurrente. \u00a0Por \u00a0el \u00a0contrario, \u00a0los \u00a0funcionarios \u00a0judiciales \u00a0deben \u00a0garantizar \u00a0la \u00a0continuidad \u00a0del \u00a0juicio oral a \u00a0efectos \u00a0de \u00a0acercarse, \u00a0lo \u00a0antes \u00a0posible, \u00a0a \u00a0la \u00a0verdad \u00a0de \u00a0lo \u00a0sucedido, e \u00a0igualmente, \u00a0para evitar situaciones que puedan llegar a afectar a las v\u00edctimas \u00a0y \u00a0a \u00a0los \u00a0testigos. \u00a0En \u00a0efecto, no escapa a la Corte el hecho que la \u00a0repetici\u00f3n \u00a0de \u00a0la \u00a0pr\u00e1ctica \u00a0de \u00a0pruebas \u00a0puede lesionar los \u00a0derechos \u00a0de \u00a0los \u00a0intervinientes \u00a0en \u00a0el \u00a0proceso penal, en especial cuando las \u00a0v\u00edctimas \u00a0sean \u00a0ni\u00f1os \u00a0o \u00a0adolescentes. \u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0las cosas, la Corte considera que las \u00a0normas \u00a0acusadas \u00a0no lesionan el derecho al debido proceso. Sin embargo, insiste \u00a0en \u00a0se\u00f1alar \u00a0que \u00a0la \u00a0repetici\u00f3n \u00a0de \u00a0las \u00a0audiencias \u00a0de juzgamiento debe ser \u00a0excepcional \u00a0y \u00a0fundada \u00a0en motivos serios y razonables, so pena de vulnerar los \u00a0derechos de las v\u00edctimas y testigos (subrayas fuera del texto). \u00a0\u00a0<\/p>\n<p>4. El desacierto del Tribunal, sin embargo, no \u00a0gener\u00f3 \u00a0consecuencias \u00a0que \u00a0requieran \u00a0enmienda, \u00a0como \u00a0bien \u00a0lo se\u00f1alaron los \u00a0representantes \u00a0de \u00a0la \u00a0Fiscal\u00eda \u00a0y \u00a0el \u00a0Ministerio \u00a0P\u00fablico, \u00a0porque de todas \u00a0maneras \u00a0atin\u00f3 \u00a0en \u00a0no \u00a0disponer \u00a0la repetici\u00f3n del juicio al estimar que ello \u00a0solo \u00a0se \u00a0debe \u00a0ordenar \u00a0cuando no exista otro medio para superar la situaci\u00f3n. \u00a0\u00a0<\/p>\n<p>5. \u00a0Cabe \u00a0resaltar \u00a0que la Sala no tendr\u00e1 en \u00a0cuenta \u00a0los documentos allegados por la procesada en memorial recibido el pasado \u00a017 \u00a0de \u00a0noviembre \u00a0del \u00a0a\u00f1o \u00a0en \u00a0curso, \u00a0toda \u00a0vez \u00a0que el tr\u00e1mite del recurso \u00a0extraordinario \u00a0no \u00a0tiene \u00a0establecido \u00a0per\u00edodo probatorio y la impugnaci\u00f3n se \u00a0debe \u00a0resolver \u00a0con \u00a0base \u00a0en \u00a0las pruebas v\u00e1lidamente practicadas en el juicio \u00a0oral. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0explic\u00f3 la falta de utilidad en la \u00a0nueva \u00a0producci\u00f3n \u00a0del \u00a0testimonio \u00a0del \u00a0menor \u00a0y \u00a0fue \u00a0claro en indicar que la \u00a0ocurrencia \u00a0 del \u00a0hecho \u00a0y \u00a0la \u00a0responsabilidad \u00a0de \u00a0NATALY \u00a0DUARTE, \u00a0encuentran \u00a0demostraci\u00f3n \u00a0en \u00a0otras \u00a0pruebas \u00a0incorporadas \u00a0con acatamiento estricto de los \u00a0principios \u00a0de \u00a0concentraci\u00f3n, \u00a0publicidad, inmediaci\u00f3n y permanencia del juez \u00a0natural. \u00a0\u00a0<\/p>\n<p>En \u00a0esa \u00a0tarea \u00a0de \u00a0estructurar \u00a0el juicio de \u00a0certeza \u00a0previamente \u00a0anunciado, \u00a0destac\u00f3 \u00a0los \u00a0relatos \u00a0suministrados \u00a0por \u00a0la \u00a0se\u00f1ora \u00a0Ruth \u00a0Orjuela \u00a0Carvajal, madre de la v\u00edctima, Mar\u00eda del Pilar Correa, \u00a0Psic\u00f3loga \u00a0de \u00a0la \u00a0Defensor\u00eda \u00a0del \u00a0Pueblo, \u00a0Enrique \u00a0Jim\u00e9nez Gait\u00e1n, perito \u00a0m\u00e9dico \u00a0del \u00a0Instituto \u00a0de \u00a0Medicina \u00a0Legal, \u00a0Martha \u00a0Janneth \u00a0Fuentes Murillo, \u00a0psic\u00f3loga \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 SIJIN, \u00a0 y \u00a0 Enrique \u00a0 Lemus \u00a0 Sarmiento, \u00a0 padre \u00a0 del \u00a0afectado. \u00a0\u00a0<\/p>\n<p>Con \u00a0fundamento \u00a0en ese referente probatorio, \u00a0expuso \u00a0desde \u00a0un \u00a0comienzo, \u00a0que \u00a0le \u00a0otorgaba plena credibilidad a la versi\u00f3n \u00a0suministrada \u00a0por el menor M.A.L.O., al m\u00e9dico legista, a su progenitora y a la \u00a0psic\u00f3loga de la SIJIN. \u00a0\u00a0<\/p>\n<p>Dada \u00a0la importancia de ese criterio, la Sala \u00a0considera \u00a0necesario \u00a0exaltar \u00a0las \u00a0glosas \u00a0de \u00a0la \u00a0colegiatura \u00a0en punto de las \u00a0pericias \u00a0incorporadas \u00a0al \u00a0proceso \u00a0porque, sin duda, servir\u00e1n para esclarecer \u00a0cualquier \u00a0inc\u00f3gnita \u00a0que \u00a0pueda \u00a0surgir \u00a0en \u00a0torno \u00a0a \u00a0su examen y consecuente \u00a0valoraci\u00f3n. \u00a0\u00a0<\/p>\n<p>Dijo el juez plural: \u00a0<\/p>\n<p>Advirti\u00f3 la doctora MARTHA JANNETH FUENTES \u00a0las \u00a0huellas \u00a0de \u00a0la \u00a0impresi\u00f3n que han dejado en la vida del menor el atentado \u00a0sexual \u00a0de \u00a0que \u00a0ha sido v\u00edctima y as\u00ed lo refiri\u00f3 en su pericia, supuesto del \u00a0cual \u00a0se \u00a0infiere \u00a0la \u00a0ocurrencia \u00a0de \u00a0las conductas il\u00edcitas, la autor\u00eda y la \u00a0consiguiente responsabilidad de NATALY DUARTE. \u00a0\u00a0<\/p>\n<p>Para \u00a0la \u00a0Sala \u00a0el \u00a0concepto pericial de la \u00a0doctora \u00a0MARTHA JANNETH FUENTES MURILLO adem\u00e1s de cumplir con las exigencias de \u00a0legalidad \u00a0en \u00a0su \u00a0descubrimiento, decreto y aducci\u00f3n, es atendible para fundar \u00a0la \u00a0sentencia \u00a0en \u00a0los \u00a0hechos \u00a0que esa prueba acredita, dada la idoneidad de la \u00a0perito \u00a0en el \u00e1rea de la psicolog\u00eda, su experiencia y dedicaci\u00f3n en el examen \u00a0de \u00a0v\u00edctimas \u00a0de \u00a0delitos \u00a0sexuales \u00a0durante \u00a0m\u00e1s de cuatro a\u00f1os en la SIJIN, \u00a0am\u00e9n de sus fundamentos cient\u00edficos. \u00a0\u00a0<\/p>\n<p>Acudi\u00f3 \u00a0la \u00a0sic\u00f3loga \u00a0FUENTES \u00a0MURILLO al \u00a0m\u00e9todo \u00a0cognitivo, \u00a0utilizando como medio la c\u00e1mara Gessel, la entrevista, los \u00a0antecedentes \u00a0de \u00a0todo \u00a0orden \u00a0de \u00a0la \u00a0infante, \u00a0la versi\u00f3n que ofreci\u00f3 de los \u00a0hechos, \u00a0los \u00a0que \u00a0examin\u00f3 \u00a0en el campo de la l\u00f3gica, la psicolog\u00eda y aplic\u00f3 \u00a0los \u00a0factores \u00a0de \u00a0credibilidad \u00a0para concluir que los hechos informados no eran \u00a0fantasiosos, \u00a0irreales, \u00a0imaginados, \u00a0por el contrario necesariamente eran fruto \u00a0de \u00a0vivencias reales de la v\u00edctima pues la informaci\u00f3n ofrecida por la memoria \u00a0epis\u00f3dica \u00a0daba \u00a0cuenta \u00a0de \u00a0detalles \u00a0que \u00a0a \u00a0esa edad no era posible haberlos \u00a0referido \u00a0sino \u00a0fuese \u00a0porque \u00a0el \u00a0menor \u00a0se \u00a0encontr\u00f3 \u00a0en \u00a0la \u00a0situaci\u00f3n \u00a0que \u00a0relata. \u00a0\u00a0<\/p>\n<p>A \u00a0continuaci\u00f3n, \u00a0expuso las razones por las \u00a0cuales \u00a0no \u00a0le \u00a0mereci\u00f3 \u00a0cr\u00e9dito la valoraci\u00f3n efectuada por la experta de la \u00a0Defensor\u00eda del Pueblo: \u00a0\u00a0<\/p>\n<p>La \u00a0comprobaci\u00f3n hecha por la sic\u00f3loga de \u00a0la \u00a0SIJIN \u00a0a \u00a0trav\u00e9s de la memoria epis\u00f3dica tiene fundamento en los conceptos \u00a0que \u00a0sustentan la ciencia de la sicolog\u00eda y constituye la raz\u00f3n por la cual la \u00a0Sala \u00a0no \u00a0le \u00a0reconoce \u00a0m\u00e9rito \u00a0al dictamen sicol\u00f3gico de la profesional de la \u00a0Defensor\u00eda \u00a0del \u00a0Pueblo, \u00a0pues \u00a0\u00e9sta \u00a0no \u00a0abord\u00f3 ese estudio con los soportes \u00a0f\u00e1cticos, \u00a0probatorios \u00a0y \u00a0profesionales \u00a0que esa situaci\u00f3n demandaba para los \u00a0efectos \u00a0de este proceso, lo que hace que ese concepto sea incompleto y por ende \u00a0su \u00a0idoneidad \u00a0no \u00a0est\u00e9 \u00a0dentro \u00a0de \u00a0las \u00a0condiciones \u00a0\u00f3ptimas requeridas para \u00a0definir el problema jur\u00eddico. \u00a0\u00a0<\/p>\n<p>Sobre las acusaciones que el menor hace a la \u00a0procesada, \u00a0la perito adscrita a la Defensor\u00eda del Pueblo sostiene que el ni\u00f1o \u00a0ha \u00a0sido \u00a0manipulado \u00a0(presi\u00f3n \u00a0ejercida por su madre para referir conductas de \u00a0tipo \u00a0sexual), \u00a0conclusi\u00f3n que apoya en las contradicciones consigo mismo y con \u00a0los \u00a0 relatos \u00a0 ofrecidos \u00a0para \u00a0otros \u00a0informes \u00a0sicol\u00f3gicos, \u00a0las \u00a0relaciones \u00a0conflictivas \u00a0de \u00a0los \u00a0padres, \u00a0am\u00e9n de que el infante \u201cno menciona vivencias \u00a0relacionadas \u00a0con \u00a0dicha \u00a0problem\u00e1tica\u201d. Estas premisas no son de recibo, por \u00a0las razones que pasan a expresarse. \u00a0\u00a0<\/p>\n<p>La \u00a0doctora \u00a0FUENTES \u00a0MURILLO \u00a0descarta esa \u00a0posibilidad \u00a0de \u00a0manipulaci\u00f3n se\u00f1alando que esa situaci\u00f3n era excluida por el \u00a0relato \u00a0que hizo el menor con base en lo que llam\u00f3 memoria epis\u00f3dica en la que \u00a0narra \u00a0 \u201cvivencias\u201d, \u00a0 expresa \u00a0 \u201csensaciones \u00a0 vividas\u201d \u00a0(describe \u00a0los \u00a0genitales \u00a0que \u00a0vio, \u00a0el dolor que sent\u00eda con la manipulaci\u00f3n, la forma en que \u00a0se \u00a0le \u00a0acariciaba) \u00a0y \u00a0as\u00ed \u00a0lo narr\u00f3 ante la progenitora y \u00e9sta lo percibi\u00f3 \u00a0cuando \u00a0el \u00a0ni\u00f1o \u00a0daba \u00a0su \u00a0versi\u00f3n \u00a0a \u00a0la \u00a0sic\u00f3loga el d\u00eda que present\u00f3 la \u00a0queja. \u00a0\u00a0<\/p>\n<p>El \u00a0relato de los hechos que el menor dio a \u00a0la \u00a0sic\u00f3loga \u00a0de la SIJIN no niega la ocurrencia de los hechos, luego no pod\u00eda \u00a0la \u00a0profesional \u00a0de \u00a0la \u00a0Defensor\u00eda \u00a0del \u00a0Pueblo generalizar, menos cuando ella \u00a0misma \u00a0en \u00a0la \u00a0base \u00a0pericial \u00a0hizo \u00a0transcripci\u00f3n \u00a0de otro informe sicol\u00f3gico \u00a0emitido \u00a0por MAR\u00cdA ALEJANDRA SAN MIGUEL, a donde los padres llevaron a M.A.L.O. \u00a0por \u00a0estos \u00a0hechos \u00a0y \u00a0en \u00a0el que el ni\u00f1o acus\u00f3 a NATALY de haberlo maltratado \u00a0sexualmente. \u00a0\u00a0<\/p>\n<p>Pero \u00a0el \u00a0argumento \u00a0de \u00a0mayor \u00a0peso \u00a0para \u00a0descalificar \u00a0el dictamen de la sic\u00f3loga de la Defensor\u00eda del Pueblo radica en \u00a0que \u00a0atribuy\u00f3 \u00a0la \u00a0manipulaci\u00f3n \u00a0a \u00a0la \u00a0madre \u00a0del \u00a0menor, \u00a0sin \u00a0darle ninguna \u00a0importancia \u00a0al siguiente hecho que no solamente lo refiri\u00f3 ella en su concepto \u00a0sino \u00a0que \u00a0ALIRIO \u00a0ENRIQUE LEMUS lo narr\u00f3 en su declaraci\u00f3n en el juicio oral. \u00a0Se \u00a0dijo \u00a0en \u00a0la p\u00e1gina n\u00famero 5 de la base pericial que se ley\u00f3 en el juicio \u00a0oral: \u00a0\u00a0<\/p>\n<p>\u201cSin \u00a0embargo \u00a0en \u00a0el informe del proceso \u00a0sicol\u00f3gico \u00a0emitido \u00a0por \u00a0la \u00a0Doctora \u00a0Mar\u00eda \u00a0Alejandra \u00a0San Miguel Psic\u00f3loga \u00a0UTII-VHV \u00a0aparece \u00a0una anotaci\u00f3n en donde se registra \u201cEl 20 de septiembre de \u00a02006; \u00a0se cita al pap\u00e1 y a la mam\u00e1 junto con el ni\u00f1o para que ellos traten de \u00a0hacer \u00a0acuerdos \u00a0en \u00a0los alimentos y las visitas; y el padre quiere que el ni\u00f1o \u00a0en \u00a0presencia \u00a0de \u00a0\u00e9l \u00a0le \u00a0diga \u00a0quien abus\u00f3 sexualmente de \u00e9l; ya que en una \u00a0terapia \u00a0anterior \u00a0el pap\u00e1 dice que el menor le comunic\u00f3 la verdad, expresando \u00a0que \u00a0fue la mam\u00e1 quien hizo esto y que ella le pidi\u00f3 que \u00e9l dijera que era la \u00a0madrastra. \u00a0En \u00a0esta \u00a0terapia \u00a0afuera \u00a0de \u00a0la \u00a0oficina \u00a0de \u00a0la \u00a0UTII; \u00a0el \u00a0pap\u00e1 \u00a0presi\u00f3nalo \u00a0(sic) \u00a0al \u00a0ni\u00f1o \u00a0para que diga que fue su mam\u00e1 y no su madrastra; \u00a0esto lo dijo el ni\u00f1o cuando ingres\u00f3 a consulta\u201d. \u00a0\u00a0<\/p>\n<p>Con \u00a0la \u00a0anterior descripci\u00f3n se establece \u00a0que \u00a0 la \u00a0 perito \u00a0 de \u00a0la \u00a0Defensor\u00eda \u00a0del \u00a0Pueblo \u00a0no \u00a0fue \u00a0objetiva \u00a0en \u00a0sus \u00a0apreciaciones, \u00a0 integralmente \u00a0no \u00a0valor\u00f3 \u00a0todas \u00a0las \u00a0circunstancias \u00a0en \u00a0los \u00a0supuestos \u00a0que \u00a0tuvo en cuenta para sus valoraciones, que a su consulta el menor \u00a0fue llevado \u00fanicamente por el padre. \u00a0\u00a0<\/p>\n<p>Los reparos examinados son suficientes para \u00a0descartar \u00a0la \u00a0opini\u00f3n \u00a0contenida \u00a0en \u00a0la pericia sicol\u00f3gica practicada por la \u00a0perita \u00a0(sic) adscrita a la Defensor\u00eda del Pueblo como fundamento probatorio de \u00a0la sentencia. \u00a0\u00a0<\/p>\n<p>El testimonio de la sic\u00f3loga de la SIJIN es \u00a0fundamento \u00a0id\u00f3neo \u00a0del \u00a0fallo \u00a0condenatorio \u00a0pues \u00a0constituye \u00a0prueba \u00a0directa \u00a0respecto \u00a0del \u00a0problema \u00a0jur\u00eddico a resolver a la que se a\u00fana la de referencia \u00a0allegada \u00a0 a \u00a0 las \u00a0 diligencias \u00a0 para \u00a0 ratificar \u00a0 la \u00a0orientaci\u00f3n \u00a0de \u00a0este \u00a0fallo16. \u00a0\u00a0<\/p>\n<p>De lo anterior se constata que el fallador, al \u00a0fijar \u00a0el m\u00e9rito suasorio del recaudo probatorio, se apoy\u00f3 expresamente en los \u00a0contenidos \u00a0de \u00a0la prueba pericial y testimonial aludida, dando cuenta detallada \u00a0de \u00a0las \u00a0razones por las cuales el examen efectuado por la sic\u00f3loga de la SIJIN \u00a0le \u00a0merece \u00a0plena \u00a0confiabilidad, en contraposici\u00f3n al estudio realizado por la \u00a0experta \u00a0 de \u00a0la \u00a0Defensor\u00eda \u00a0del \u00a0Pueblo, \u00a0cuyas \u00a0deficiencias \u00a0se \u00a0ocup\u00f3 \u00a0de \u00a0resaltar. \u00a0\u00a0<\/p>\n<p>A \u00a0 partir \u00a0de \u00a0esa \u00a0premisa, \u00a0desech\u00f3 \u00a0la \u00a0posibilidad \u00a0de \u00a0que el menor hubiese recreado la informaci\u00f3n que suministr\u00f3 a \u00a0su \u00a0progenitora \u00a0y a los profesionales de la medicina y la sicolog\u00eda, sobre las \u00a0lascivas \u00a0conductas ejecutadas en sus partes \u00edntimas, pues si bien se presentan \u00a0algunas \u00a0inconsistencias en cuanto a fechas y n\u00famero de veces, en lo sustancial \u00a0siempre \u00a0fue \u00a0uniforme \u00a0en \u00a0sostener \u00a0d\u00f3nde \u00a0ocurrieron \u00a0los hechos, qui\u00e9n los \u00a0ejecut\u00f3 y a qu\u00e9 vej\u00e1menes fue sometido. \u00a0\u00a0<\/p>\n<p>Esa \u00a0apreciaci\u00f3n \u00a0anal\u00edtica se ve reforzada \u00a0con \u00a0la subsiguiente declaraci\u00f3n del juzgador plural, quien adujo, sin asomo de \u00a0duda, \u00a0que \u00a0la \u00a0conducta \u00a0fue \u00a0ejecutada \u00a0por \u00a0NATALY \u00a0DUARTE cuando hac\u00eda vida \u00a0marital \u00a0con \u00a0Alirio \u00a0Enrique \u00a0Lemus, en la casa de \u00e9ste, en momentos en que se \u00a0ocupaba \u00a0de \u00a0ba\u00f1ar y vestir al ni\u00f1o, deduciendo as\u00ed, la agravante descrita en \u00a0el \u00a0numeral \u00a02\u00ba \u00a0del \u00a0art\u00edculo \u00a0211 \u00a0del \u00a0C\u00f3digo \u00a0Penal, \u00a0consistente \u00a0en que \u00a0\u201c[e]l \u00a0responsable \u00a0tuviere \u00a0cualquier \u00a0car\u00e1cter, \u00a0posici\u00f3n \u00a0o \u00a0cargo \u00a0que \u00a0le \u00a0d\u00e9 \u00a0particular \u00a0autoridad \u00a0sobre la v\u00edctima o la \u00a0impulse a depositar en \u00e9l su confianza\u201d. \u00a0\u00a0<\/p>\n<p>De \u00a0 esta \u00a0 manera, \u00a0 se \u00a0advierte \u00a0que \u00a0la \u00a0responsabilidad \u00a0endilgada \u00a0a \u00a0la \u00a0se\u00f1ora \u00a0NATALY \u00a0DUARTE, \u00a0es \u00a0el fruto de una \u00a0valoraci\u00f3n \u00a0objetiva, \u00a0articulada \u00a0y \u00a0razonada, \u00a0que \u00a0impide \u00a0predicar defectos \u00a0sustanciales \u00a0en \u00a0el \u00a0raciocinio \u00a0del \u00a0Tribunal, dado que sus juicios no denotan \u00a0capricho \u00a0o \u00a0arbitrariedad, ni contienen la declaraci\u00f3n de una verdad contraria \u00a0a la realidad que revela el proceso.\u00a0 \u00a0\u00a0<\/p>\n<p>En \u00a0estas condiciones, como lo solicitaron la \u00a0Fiscal\u00eda \u00a0 y \u00a0 el \u00a0Ministerio \u00a0P\u00fablico, \u00a0la \u00a0Corte \u00a0no \u00a0casar\u00e1 \u00a0la \u00a0sentencia \u00a0impugnada. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n \u00a0Penal \u00a0de \u00a0la \u00a0Corte \u00a0Suprema \u00a0de Justicia, administrando justicia en \u00a0nombre de la Rep\u00fablica y por autoridad de la ley, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0\u00a0<\/p>\n<p>PRIMERO. \u00a0NO \u00a0 \u00a0CASAR \u00a0 el \u00a0 fallo \u00a0impugnado. \u00a0\u00a0<\/p>\n<p>SEGUNDO. Contra esta \u00a0decisi\u00f3n no procede recurso alguno. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese \u00a0y \u00a0devu\u00e9lvase \u00a0al Tribunal de \u00a0origen. \u00a0\u00a0<\/p>\n<p>Jos\u00e9 Leonidas Bustos Mart\u00ednez \u00a0<\/p>\n<p>Jos\u00e9 Luis \u00a0Barcel\u00f3 Camacho \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Fernando Alberto Castro Caballero \u00a0<\/p>\n<p>Eugenio Fern\u00e1ndez Carlier \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Mar\u00eda \u00a0 \u00a0del \u00a0 \u00a0Rosario \u00a0 \u00a0Gonz\u00e1lez \u00a0Mu\u00f1oz \u00a0<\/p>\n<p>Gustavo Enrique Malo Fern\u00e1ndez \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Eyder Pati\u00f1o Cabrera \u00a0<\/p>\n<p>Luis Guillermo Salazar Otero \u00a0<\/p>\n<p>Nubia Yolanda Nova Garc\u00eda \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 \u00a0En \u00a0virtud \u00a0de \u00a0lo previsto en el C\u00f3digo de la Infancia y la Adolescencia, se omite \u00a0consignar el nombre del menor v\u00edctima. \u00a0\u00a0<\/p>\n<p>2 Fls \u00a010 y 11 de la carpeta. \u00a0\u00a0<\/p>\n<p>3 Fls \u00a022 a 25 \u00edd. \u00a0\u00a0<\/p>\n<p>4 Fl 35 \u00a0\u00edd. \u00a0\u00a0<\/p>\n<p>5 Fls \u00a094 a 97 \u00edd. \u00a0\u00a0<\/p>\n<p>6 Fls \u00a0106, 145 y 146, 156, 169 y 170, 246, 250, 270 y 271 y 283, \u00cdd. \u00a0\u00a0<\/p>\n<p>7 Fls \u00a0289 a 299 \u00edd. \u00a0\u00a0<\/p>\n<p>8 Fls \u00a012 a 37 C. Tribunal. \u00a0\u00a0<\/p>\n<p>9 Fl 18 \u00a0C.Tribunal. \u00a0\u00a0<\/p>\n<p>10 Cfr \u00a0sentencias \u00a0del \u00a030 \u00a0de enero de 2008, radicado No 27192, y 20 de enero de 2010, \u00a0radicado Nos 32196, entre otras. \u00a0\u00a0<\/p>\n<p>11 \u00a0Sentencia del 20 de enero de 2011, radicado No 32556. \u00a0\u00a0<\/p>\n<p>12 \u00a0Sentencia del 12 de diciembre de 2012, radicado No 38512. \u00a0\u00a0<\/p>\n<p>13 \u00a0As\u00ed, \u00a0los \u00a0art\u00edculos \u00a044 \u00a0de la Constituci\u00f3n Nacional, y 6\u00ba, 8\u00ba y 9\u00ba de la \u00a0Ley 1098 de 2006. \u00a0\u00a0<\/p>\n<p>14 La \u00a0Convenci\u00f3n \u00a0sobre \u00a0los \u00a0Derechos \u00a0del \u00a0Ni\u00f1o- \u00a0art\u00edculo \u00a03\u00ba-, adoptada por la \u00a0Asamblea \u00a0General de las Naciones Unidas el 20 de noviembre de 1989, aprobada en \u00a0Colombia \u00a0por la Ley 12 de 1991 y ratificada el 20 de febrero del mismo a\u00f1o; el \u00a0acto \u00a0 \u00a0Internacional \u00a0 \u00a0de \u00a0 Derechos \u00a0 Civiles \u00a0 y \u00a0 Pol\u00edticos \u00a0 \u2013art\u00edculo \u00a0 24-1; \u00a0 la \u00a0 Convenci\u00f3n \u00a0Americana \u00a0 de \u00a0 Derechos \u00a0 Humanos \u00a0 \u2013art\u00edculo \u00a019-; \u00a0la \u00a0Declaraci\u00f3n \u00a0de \u00a0las \u00a0Naciones \u00a0Unidas \u00a0sobre \u00a0Derechos \u00a0 \u00a0 \u00a0del \u00a0 \u00a0 \u00a0Ni\u00f1o \u00a0 \u00a0 \u00a0\u2013Principio \u00a02- \u00a0y, \u00a0tambi\u00e9n, \u00a0la Declaraci\u00f3n Universal de Derechos \u00a0Humanos \u00a0 \u00a0 \u00a0 de \u00a0 \u00a0 \u00a0 1948 \u00a0 \u00a0 \u00a0 \u2013art\u00edculo 25-2-. \u00a0\u00a0<\/p>\n<p>15 Cfr \u00a0sentencias \u00a0 T-408 \u00a0 de \u00a0 1995, \u00a0 T-514 \u00a0 de \u00a0 1998 \u00a0 y \u00a0T-979 \u00a0de \u00a02001, \u00a0entre \u00a0otras. \u00a0\u00a0<\/p>\n<p>16 Cfr \u00a0fls 25 a 27 C. Tribunal. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 MAGISTRADO PONENTE \u00a0 EYDER PATI\u00d1O CABRERA \u00a0 Aprobado: Acta No. 386- \u00a0 Bogot\u00e1. \u00a0D.C., \u00a0veinte (20) de noviembre de dos mil trece \u00a0(2013) \u00a0\u00a0 MOTIVO DE LA DECISI\u00d3N \u00a0 Decide \u00a0la \u00a0Sala \u00a0el \u00a0recurso \u00a0de \u00a0casaci\u00f3n \u00a0interpuesto \u00a0por \u00a0el defensor de NATALY DUARTE, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-25537","post","type-post","status-publish","format-standard","hentry","category-21"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/25537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=25537"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/25537\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=25537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=25537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=25537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}