{"id":25297,"date":"2023-09-12T17:23:42","date_gmt":"2023-09-12T17:23:42","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/4014728-11-12\/"},"modified":"2023-09-12T17:23:42","modified_gmt":"2023-09-12T17:23:42","slug":"4014728-11-12","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/4014728-11-12\/","title":{"rendered":"40147(28-11-12)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA \u00a0 DE \u00a0 CASACI\u00d3N \u00a0PENAL \u00a0\u00a0<\/p>\n<p>Magistrado \u00a0Ponente \u00a0\u00a0<\/p>\n<p>FERNANDO ALBERTO CASTRO CABALLERO \u00a0<\/p>\n<p>Aprobado \u00a0acta N\u00ba \u00a0436 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D.C., \u00a0veintiocho de noviembre de dos mil doce (2012). \u00a0\u00a0<\/p>\n<p>V \u00a0 I \u00a0 S \u00a0 T \u00a0 O \u00a0S \u00a0\u00a0<\/p>\n<p>La \u00a0Sala \u00a0resuelve \u00a0la \u00a0admisibilidad de la \u00a0demanda \u00a0 \u00a0de \u00a0 casaci\u00f3n \u00a0 presentada \u00a0 por \u00a0 el \u00a0 defensor \u00a0 de \u00a0 Diomedes \u00a0 \u00a0 \u00a0 Rafael \u00a0 \u00a0 \u00a0S\u00e1nchez \u00a0 \u00a0 \u00a0De \u00a0 \u00a0 \u00a0Castro, \u00a0contra \u00a0la \u00a0sentencia \u00a0dictada \u00a0por \u00a0el Tribunal Superior de Bogot\u00e1, el 7 de junio de 2012, \u00a0mediante \u00a0la cual revoc\u00f3 la proferida por el Juzgado Segundo Penal del Circuito \u00a0de \u00a0Descongesti\u00f3n \u00a0de la misma ciudad, el 8 de noviembre de 2011, y lo conden\u00f3 \u00a0como coautor de los delitos de fraude procesal y estafa agravada. \u00a0\u00a0<\/p>\n<p>HECHOS Y ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>1. \u00a0Los primeros fueron sintetizados por el \u00a0juzgador de segundo grado de la siguiente manera: \u00a0\u00a0<\/p>\n<p>\u201cJos\u00e9 Mart\u00ednez Caballero, como apoderado \u00a0de \u00a0Julia \u00a0Noguera \u00a0de \u00a0Dangond, c\u00f3nyuge sobreviviente del ex congresista Julio \u00a0Dangond \u00a0Ovalle, present\u00f3 en el tr\u00e1mite pensional que adelantaba ante el Fondo \u00a0de \u00a0Previsi\u00f3n \u00a0Social \u00a0del \u00a0Congreso \u00a0de \u00a0la \u00a0Rep\u00fablica, \u00a0las \u00a0certificaciones \u00a0expedidas \u00a0el \u00a017 \u00a0de \u00a0junio \u00a0y \u00a0el 11 de julio de 1997 por Diomedes S\u00e1nchez De \u00a0Castro \u00a0(procesado \u00a0en \u00a0esta \u00a0actuaci\u00f3n), quien para esa \u00e9poca se desempe\u00f1aba \u00a0como \u00a0Secretario \u00a0General \u00a0de \u00a0la \u00a0Asamblea \u00a0Departamental \u00a0del \u00a0Magdalena, \u00a0que \u00a0conten\u00edan \u00a0informaci\u00f3n \u00a0falsa \u00a0sobre \u00a0la vinculaci\u00f3n y tiempo de servicio del \u00a0causante \u00a0en \u00a0esa entidad p\u00fablica, que sirvieron de base para la expedici\u00f3n de \u00a0la \u00a0Resoluci\u00f3n \u00a0N\u00b0 \u00a01007 del 21 de noviembre de 1997, en la que se ordenaba el \u00a0reconocimiento \u00a0y \u00a0pago \u00a0de la pensi\u00f3n mensual vitalicia de jubilaci\u00f3n a favor \u00a0de la solicitante\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a02. \u00a0Por \u00a0los \u00a0anteriores \u00a0hechos, \u00a0la \u00a0Fiscal\u00eda \u00a0General \u00a0de la Naci\u00f3n, el 26 de julio de 2005, profiri\u00f3 resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n \u00a0contra \u00a0Diomedes \u00a0S\u00e1nchez \u00a0De \u00a0Castro por el delito de falsedad \u00a0ideol\u00f3gica \u00a0en \u00a0documento \u00a0p\u00fablico. \u00a0As\u00ed \u00a0mismo, \u00a0precluy\u00f3 la investigaci\u00f3n \u00a0respecto de los punibles de fraude procesal y estafa agravada. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Apelada \u00a0la \u00a0anterior decisi\u00f3n por el apoderado de la parte civil, \u00a0la \u00a0Fiscal\u00eda \u00a046 \u00a0Delegada \u00a0ante \u00a0el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1, el 10 de \u00a0septiembre \u00a0de \u00a02009, \u00a0la \u00a0revoc\u00f3, en tanto profiri\u00f3 resoluci\u00f3n de acusaci\u00f3n \u00a0contra \u00a0el \u00a0procesado \u00a0por \u00a0las \u00a0conductas \u00a0punibles de fraude procesal y estafa \u00a0agravada. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0En \u00a0ese \u00a0pronunciamiento, \u00a0declar\u00f3 \u00a0la \u00a0extinci\u00f3n \u00a0de \u00a0la acci\u00f3n \u00a0penal\u00a0 \u00a0por \u00a0raz\u00f3n \u00a0de \u00a0la \u00a0prescripci\u00f3n \u00a0de \u00a0la \u00a0infracci\u00f3n de falsedad \u00a0ideol\u00f3gica en documento p\u00fablico. \u00a0\u00a0<\/p>\n<p>3. \u00a0El \u00a0expediente pas\u00f3 al Juzgado Segundo \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Descongesti\u00f3n \u00a0de \u00a0Bogot\u00e1, \u00a0autoridad \u00a0que \u00a0el \u00a08 de \u00a0noviembre \u00a0de \u00a02011, \u00a0profiri\u00f3 \u00a0sentencia en la que absolvi\u00f3 a Diomedes Rafael \u00a0S\u00e1nchez De Castro de los cargos atribuidos en la acusaci\u00f3n. \u00a0\u00a0<\/p>\n<p>4.\u00a0 Apelado el fallo por la Fiscal\u00eda, \u00a0el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1, \u00a0el \u00a07 \u00a0de \u00a0junio \u00a0de \u00a02012, \u00a0lo revoc\u00f3 y, \u00a0consecuentemente, \u00a0conden\u00f3 a Diomedes S\u00e1nchez De Castro a la pena principal de \u00a082.32 \u00a0meses \u00a0de \u00a0prisi\u00f3n, \u00a0multa de 260.49 salarios m\u00ednimos legales mensuales \u00a0vigentes \u00a0e \u00a0inhabilitaci\u00f3n para el ejercicio de derechos y funciones p\u00fablicas \u00a0por \u00a0el \u00a0mismo \u00a0t\u00e9rmino \u00a0de \u00a0la \u00a0privativa \u00a0de la libertad, como coautor de las \u00a0conductas punibles de fraude procesal y estafa agravada. \u00a0\u00a0<\/p>\n<p>6. Contra la anterior decisi\u00f3n el defensor \u00a0de \u00a0 \u00a0 S\u00e1nchez \u00a0 \u00a0 De \u00a0 \u00a0 Castro \u00a0 \u00a0 interpuso recurso de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>L \u00a0A\u00a0\u00a0\u00a0\u00a0 D E M A N D A\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Con \u00a0base \u00a0en \u00a0la causal primera, seg\u00fan la \u00a0sistem\u00e1tica \u00a0reglada \u00a0en \u00a0la \u00a0Ley 600 de 2000,\u00a0 presenta un s\u00f3lo reproche \u00a0contra el fallo, as\u00ed: \u00a0\u00a0<\/p>\n<p>\u00danico cargo \u00a0<\/p>\n<p>Argumenta \u00a0que acude a la causal primera de \u00a0casaci\u00f3n, \u00a0por \u00a0cuanto \u00a0la \u00a0sentencia \u00a0es \u00a0violatoria de una norma de car\u00e1cter \u00a0sustancial, \u00a0por falta de aplicaci\u00f3n del art\u00edculo 182 del Decreto 100 de 1980, \u00a0y aplicaci\u00f3n indebida del art\u00edculo 453 de la Ley 599 de 2000. \u00a0\u00a0<\/p>\n<p>El \u00a0casacionista \u00a0inicialmente cita algunos \u00a0fragmentos \u00a0del \u00a0fallo recurrido y luego de referirse a la imputaci\u00f3n jur\u00eddica \u00a0atribuida \u00a0a \u00a0su \u00a0defendido \u00a0en \u00a0la \u00a0resoluci\u00f3n \u00a0de \u00a0acusaci\u00f3n, \u00a0menciona \u00a0una \u00a0decisi\u00f3n \u00a0de \u00a0esta \u00a0Sala \u00a0de \u00a0la \u00a0Corte, \u00a0para \u00a0luego manifestar que la norma a \u00a0aplicar es el art\u00edculo 182 del C\u00f3digo Penal de 1980. \u00a0\u00a0<\/p>\n<p>En \u00a0esa \u00a0medida, \u00a0colige \u00a0que \u00a0el \u00a0vicio es \u00a0trascendente, \u00a0en \u00a0la medida en que al aplicar el art\u00edculo 453 de la Ley 599 de \u00a02000, \u00a0 se \u00a0impidi\u00f3 \u00a0que \u00a0a \u00a0su \u00a0procurado \u00a0se \u00a0le \u00a0concediera \u00a0los \u00a0mecanismos \u00a0sustitutivos\u00a0 de la pena de prisi\u00f3n. \u00a0\u00a0<\/p>\n<p>Por \u00a0tanto, \u00a0pide \u00a0a \u00a0la \u00a0Corte \u00a0casar \u00a0la \u00a0sentencia impugnada. \u00a0\u00a0<\/p>\n<p>ALEGATOS DEL NO RECURRENTE \u00a0<\/p>\n<p>En primer lugar, solicita a la Corporaci\u00f3n \u00a0que \u00a0inadmita \u00a0la \u00a0demanda de casaci\u00f3n, toda vez que el censor limit\u00f3 la labor \u00a0argumentativa \u00a0a \u00a0citar \u00a0al \u00a0Tribunal, \u00a0pero \u00a0no \u00a0presenta argumento tendiente a \u00a0debatir sus consideraciones. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0De \u00a0otro \u00a0lado, estima que el planteamiento del censor, respecto de \u00a0que \u00a0la \u00a0norma \u00a0aplicar \u00a0era \u00a0el \u00a0art\u00edculo 182 del Decreto 100 de 1980, tampoco \u00a0tiene \u00a0vocaci\u00f3n de \u00e9xito, seg\u00fan lo ha plasmado la abundante jurisprudencia de \u00a0la \u00a0Corte\u00a0 \u00a0acerca \u00a0de \u00a0los \u00a0delitos de car\u00e1cter permanente como el fraude \u00a0procesal. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES\u00a0 \u00a0DE\u00a0 \u00a0LA\u00a0 \u00a0SALA \u00a0\u00a0<\/p>\n<p>La \u00a0 casaci\u00f3n \u00a0 en \u00a0 la \u00a0 Ley \u00a0 600 \u00a0 de \u00a02000 \u00a0\u00a0<\/p>\n<p>En \u00a0raz\u00f3n del car\u00e1cter extraordinario y \u00a0rogado \u00a0de \u00a0la \u00a0casaci\u00f3n, \u00a0al \u00a0libelista \u00a0compete \u00a0elaborar la demanda bajo los \u00a0estrictos \u00a0 par\u00e1metros \u00a0 contemplados \u00a0 en \u00a0 la \u00a0 ley \u00a0 y \u00a0 decantados \u00a0por \u00a0la \u00a0jurisprudencia. \u00a0\u00a0<\/p>\n<p>Por \u00a0tanto, \u00a0no basta con afirmar que en la \u00a0sentencia \u00a0o \u00a0al \u00a0interior \u00a0del \u00a0proceso \u00a0se cometi\u00f3 un error in iudicando o de \u00a0actividad, \u00a0dado \u00a0que \u00a0adem\u00e1s \u00a0debe \u00a0demostrar \u00a0la \u00a0existencia \u00a0del \u00a0vicio y su \u00a0trascendencia \u00a0 \u00a0frente \u00a0 \u00a0a \u00a0 las \u00a0 plurales \u00a0 decisiones \u00a0 adoptadas \u00a0 en \u00a0 el \u00a0fallo. \u00a0\u00a0<\/p>\n<p>De acuerdo con la jurisprudencia de la Sala, \u00a0es \u00a0bien \u00a0sabido \u00a0que \u00a0el \u00a0recurso de casaci\u00f3n se constituye en el medio por el \u00a0cual \u00a0la \u00a0Corporaci\u00f3n \u00a0revisa \u00a0la \u00a0legalidad \u00a0de \u00a0la \u00a0sentencia. De ah\u00ed que la \u00a0demanda \u00a0ha de cumplir las formalidades estatuidas en el art\u00edculo 212 de la Ley \u00a0600 \u00a0de \u00a02000, toda vez que en ella se debe se\u00f1alar, de manera clara y precisa, \u00a0la \u00a0causal con la cual se pretende la infirmaci\u00f3n del fallo, argumentando c\u00f3mo \u00a0el \u00a0vicio \u00a0en \u00a0la \u00a0adjudicaci\u00f3n \u00a0de \u00a0la \u00a0norma o in procedendo, seg\u00fan el caso, \u00a0condujo a resquebrajar la providencia. \u00a0\u00a0<\/p>\n<p>As\u00ed, no resulta atinado denunciar s\u00f3lo la \u00a0existencia \u00a0del \u00a0vicio \u00a0que \u00a0se \u00a0invoca \u00a0sino que al casacionista le corresponde \u00a0demostrar \u00a0c\u00f3mo \u00a0el \u00a0mismo \u00a0tiene \u00a0la \u00a0trascendencia \u00a0suficiente para romper la \u00a0sentencia \u00a0de \u00a0segunda \u00a0instancia y, por lo mismo, obligue a la Corte intervenir \u00a0como \u00a0Tribunal \u00a0de \u00a0Casaci\u00f3n \u00a0en \u00a0procura \u00a0de \u00a0reparar, \u00a0entre otros fines, los \u00a0agravios \u00a0 inferidos \u00a0 a \u00a0 los \u00a0 intervinientes \u00a0 en \u00a0 el \u00a0 proceso \u00a0 objeto \u00a0de \u00a0censura. \u00a0\u00a0<\/p>\n<p>Presupuestos \u00a0 de \u00a0 l\u00f3gica \u00a0 y \u00a0 debida \u00a0fundamentaci\u00f3n de la causal primera de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Cuando el yerro se postula por la v\u00eda de la \u00a0infracci\u00f3n \u00a0directa de la ley sustancial, el casacionista acepta que las hechos \u00a0declarados \u00a0como \u00a0probados, \u00a0devienen \u00a0necesariamente \u00a0de una correcta actividad \u00a0probatoria, \u00a0raz\u00f3n \u00a0por \u00a0la cual el debate se circunscribe a la aplicaci\u00f3n del \u00a0derecho, \u00a0sin que tengan cabida aspectos relacionados con la credibilidad de los \u00a0elementos de juicio y el acontecer f\u00e1ctico. \u00a0\u00a0<\/p>\n<p>En esa medida, la labor de demostraci\u00f3n de \u00a0la \u00a0trascendencia \u00a0del \u00a0vicio \u00a0deber\u00e1 \u00a0estar \u00a0sustentada \u00a0en \u00a0evidenciar que el \u00a0juzgador \u00a0seleccion\u00f3 \u00a0una \u00a0norma \u00a0que \u00a0no \u00a0era la llamada a gobernar el asunto, \u00a0omiti\u00f3 \u00a0otra \u00a0que s\u00ed resolv\u00eda los extremos de la relaci\u00f3n jur\u00eddico procesal \u00a0o, \u00a0habi\u00e9ndola \u00a0escogido correctamente, le dio un alcance interpretativo que no \u00a0se deriva del texto de la ley. \u00a0\u00a0<\/p>\n<p>De acuerdo con los anteriores presupuestos, \u00a0la \u00a0Corte \u00a0advierte que el cargo postulado contra el fallo de segunda instancia, \u00a0no \u00a0fue \u00a0elaborado \u00a0siguiendo \u00a0esos derroteros, raz\u00f3n por la cual, desde ya, se \u00a0anuncia la inadmisi\u00f3n del libelo. \u00a0\u00a0<\/p>\n<p>En \u00a0 relaci\u00f3n \u00a0 con \u00a0 el \u00a0 \u00fanico \u00a0reproche, \u00a0como \u00a0atinadamente lo \u00a0adujo \u00a0el \u00a0apoderado \u00a0de \u00a0la \u00a0parte civil como sujeto procesal no recurrente, el \u00a0actor \u00a0lo \u00a0dej\u00f3 a mitad de camino, en la medida en que no present\u00f3 argumentos, \u00a0en \u00a0orden \u00a0a \u00a0demostrar \u00a0la \u00a0equivocaci\u00f3n \u00a0del \u00a0sentenciador \u00a0al seleccionar el \u00a0precepto llamado a gobernar el asunto. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, \u00a0la labor de fundamentaci\u00f3n el \u00a0demandante \u00a0la hizo consistir en presentar personales opiniones, en cuanto a que \u00a0la \u00a0norma a aplicar, respecto del punible de fraude procesal, era la contemplada \u00a0en \u00a0el \u00a0art\u00edculo \u00a0182 \u00a0del Decreto Ley 100 de 1980 y no el 453 de la Ley 599 de \u00a02000. \u00a0\u00a0<\/p>\n<p>Sin \u00a0embargo, \u00a0en \u00a0manera \u00a0alguna demostr\u00f3 \u00a0c\u00f3mo \u00a0la \u00a0selecci\u00f3n normativa hecha por el Tribunal era equivocada, puesto que \u00a0su \u00a0discurso \u00a0\u00fanicamente \u00a0lo \u00a0limit\u00f3 \u00a0a \u00a0transcribir \u00a0varios \u00a0fragmentos de la \u00a0sentencia \u00a0recurrida \u00a0y \u00a0citar la calificaci\u00f3n jur\u00eddica atribuida al procesado \u00a0en la resoluci\u00f3n de acusaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Es \u00a0 decir, \u00a0el \u00a0libelista \u00a0no \u00a0present\u00f3 \u00a0argumento \u00a0alguno, \u00a0en \u00a0orden \u00a0a demostrar la aplicaci\u00f3n indebida del art\u00edculo \u00a0453 \u00a0del \u00a0C\u00f3digo \u00a0Penal \u00a0de 2000 y la exclusi\u00f3n evidente del art\u00edculo 182 del \u00a0Decreto Ley 100 de 1980. \u00a0\u00a0<\/p>\n<p>Al \u00a0 respecto \u00a0vale \u00a0resaltar \u00a0que \u00a0a \u00a0la \u00a0aplicaci\u00f3n \u00a0indebida como motivo de la infracci\u00f3n directa de la ley sustancial \u00a0llega \u00a0el \u00a0juzgador\u00a0 \u00a0al \u00a0cometer \u00a0un \u00a0error \u00a0de adecuaci\u00f3n t\u00edpica, en la \u00a0medida \u00a0en \u00a0que existe una equivocaci\u00f3n en el proceso de selecci\u00f3n de la norma \u00a0aplicable \u00a0al \u00a0caso \u00a0concreto, \u00a0por no ser la que lo contempla. Es decir, hay un \u00a0desatino de diagnosis jur\u00eddica. \u00a0\u00a0<\/p>\n<p>Por tanto, los fundamentos jur\u00eddicos de la \u00a0alegaci\u00f3n \u00a0deben \u00a0estar \u00a0orientados \u00a0a \u00a0demostrar \u00a0que \u00a0por \u00a0la \u00a0forma \u00a0como se \u00a0apreciaron \u00a0los \u00a0hechos que originaron el proceso y las pruebas que respaldan el \u00a0fallo, \u00a0 la \u00a0 norma \u00a0 que \u00a0 se \u00a0 aplic\u00f3 \u00a0 no \u00a0 es \u00a0 la \u00a0que \u00a0regula \u00a0al \u00a0asunto \u00a0debatido. \u00a0\u00a0<\/p>\n<p>De otra parte, se incurre en la exclusi\u00f3n \u00a0evidente, \u00a0 igualmente \u00a0como \u00a0motivo \u00a0de \u00a0la \u00a0violaci\u00f3n \u00a0directa \u00a0de \u00a0la \u00a0norma \u00a0sustancial, \u00a0cuando \u00a0el \u00a0sentenciador \u00a0deja \u00a0de \u00a0aplicar \u00a0el \u00a0precepto llamado a \u00a0gobernar \u00a0el \u00a0asunto, \u00a0el que en rigor y derecho se adecuaban los hechos materia \u00a0de \u00a0juzgamiento. \u00a0Por \u00a0tanto, \u00a0la \u00a0labor \u00a0del \u00a0libelista \u00a0debe \u00a0estar dirigida a \u00a0demostrar \u00a0la citada equivocaci\u00f3n del juzgador en la elaboraci\u00f3n del juicio de \u00a0derecho. \u00a0\u00a0<\/p>\n<p>Los anteriores presupuestos fueron omitidos \u00a0por \u00a0el \u00a0casacionista, \u00a0raz\u00f3n \u00a0por la cual la Corte, atendiendo al principio de \u00a0limitaci\u00f3n, \u00a0carece \u00a0de \u00a0la facultad de complementarlo, por lo que el libelo se \u00a0inadmitir\u00e1. \u00a0\u00a0<\/p>\n<p>De \u00a0otro \u00a0lado, la Sala considera oportuno \u00a0reiterar \u00a0que \u00a0el \u00a0tema planteado por el censor, en cuanto a la norma a aplicar, \u00a0respecto \u00a0de \u00a0los \u00a0delitos \u00a0denominados \u00a0por \u00a0la \u00a0doctrina \u00a0como \u00a0de \u00a0ejecuci\u00f3n \u00a0permanente, \u00a0ha \u00a0sido \u00a0tratado \u00a0en \u00a0m\u00faltiples pronunciamientos, entre ellos, en \u00a0sentencia \u00a0de \u00a025 \u00a0agosto \u00a0de \u00a02010, \u00a0en \u00a0la \u00a0que \u00a0textualmente \u00a0la Corporaci\u00f3n \u00a0dijo: \u00a0\u00a0<\/p>\n<p>\u201cEn dicha labor encuentra la Colegiatura \u00a0que \u00a0trat\u00e1ndose \u00a0de \u00a0delitos permanentes cuya comisi\u00f3n comenz\u00f3 en vigencia de \u00a0una \u00a0ley, \u00a0pero \u00a0que \u00a0se \u00a0posterg\u00f3 \u00a0hasta \u00a0el \u00a0advenimiento de una legislaci\u00f3n \u00a0posterior \u00a0m\u00e1s gravosa, se impone aplicar esta \u00faltima normatividad, de acuerdo \u00a0con las siguientes razones: \u00a0\u00a0<\/p>\n<p>\u201cPrimera, \u00a0no \u00a0tienen \u00a0ocurrencia \u00a0los \u00a0presupuestos \u00a0para \u00a0dar aplicaci\u00f3n al principio de favorabilidad por v\u00eda de la \u00a0ultraactividad \u00a0de \u00a0la norma vigente para cuando inici\u00f3 el comportamiento, pues \u00a0dicho \u00a0principio \u00a0se \u00a0aplica cuando dos legislaciones en tr\u00e1nsito legislativo o \u00a0coexistentes \u00a0se \u00a0ocupan \u00a0de regular de manera diferente, entre otros casos, las \u00a0consecuencias \u00a0punitivas \u00a0de un mismo comportamiento determinado, de modo que se \u00a0acoge la sanci\u00f3n m\u00e1s beneficiosa para el procesado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u201cSiendo \u00a0ello \u00a0as\u00ed, \u00a0palmario resulta que no opera el mencionado \u00a0principio \u00a0trat\u00e1ndose \u00a0de \u00a0delitos \u00a0permanentes, pues el tramo cometido bajo el \u00a0imperio \u00a0de \u00a0una \u00a0legislaci\u00f3n ben\u00e9vola, no es el mismo acaecido en vigencia de \u00a0una \u00a0nueva \u00a0ley \u00a0m\u00e1s \u00a0gravosa, \u00a0en \u00a0cuanto difieren, por lo menos en el aspecto \u00a0temporal, \u00a0as\u00ed \u00a0se \u00a0trate del mismo \u00e1mbito espacial, pues el tiempo durante el \u00a0cual \u00a0se \u00a0ha lesionado el bien jur\u00eddico objeto de protecci\u00f3n penal en vigencia \u00a0de \u00a0la \u00a0nueva \u00a0legislaci\u00f3n m\u00e1s severa, es ontol\u00f3gicamente diferente del lapso \u00a0de \u00a0quebranto \u00a0acaecido \u00a0bajo \u00a0el \u00a0imperio \u00a0de \u00a0la \u00a0anterior \u00a0normatividad \u00a0m\u00e1s \u00a0ben\u00e9vola. \u00a0\u00a0<\/p>\n<p>\u201cSegunda, si en materia de aplicaci\u00f3n de \u00a0las \u00a0 normas \u00a0 penales \u00a0en \u00a0el \u00a0tiempo \u00a0rigen \u00a0los \u00a0principios \u00a0de \u00a0legalidad \u00a0e \u00a0irretroactividad, \u00a0en virtud de los cuales, la ley gobierna los hechos cometidos \u00a0durante \u00a0su \u00a0vigencia, \u00a0es \u00a0claro \u00a0que \u00a0si \u00a0se \u00a0aplicara \u00a0la \u00a0norma inicial m\u00e1s \u00a0beneficiosa, \u00a0se dejar\u00eda impune, sin m\u00e1s, el aparte de la comisi\u00f3n del delito \u00a0que \u00a0 se \u00a0 desarroll\u00f3 \u00a0 bajo \u00a0 la \u00a0 \u00e9gida \u00a0 de \u00a0 la \u00a0nueva \u00a0legislaci\u00f3n \u00a0m\u00e1s \u00a0gravosa. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cTercera, si de acuerdo con el art\u00edculo \u00a06\u00ba \u00a0de \u00a0la Carta Pol\u00edtica, las personas pueden realizar todo aquello que no se \u00a0encuentre \u00a0expresa, \u00a0clara \u00a0y previamente definido como punible, es evidente que \u00a0cuando \u00a0acomodan \u00a0su \u00a0proceder \u00a0a un tipo penal sin justificaci\u00f3n atendible, se \u00a0hacen acreedoras a la pena dispuesta en el respectivo precepto. \u00a0\u00a0<\/p>\n<p>\u201cCuarta, \u00a0obs\u00e9rvese \u00a0que \u00a0si \u00a0a quienes \u00a0comenzaron \u00a0el \u00a0delito \u00a0en \u00a0vigencia \u00a0de \u00a0la ley anterior se les aplicara la ley \u00a0ben\u00e9vola \u00a0de manera ultraactiva con posterioridad a su derogatoria, obtendr\u00edan \u00a0un \u00a0beneficio \u00a0indebido, \u00a0pues \u00a0si \u00a0otras personas cometieran el mismo delito en \u00a0vigencia \u00a0de \u00a0la nueva legislaci\u00f3n se les impondr\u00eda esa pena m\u00e1s grave, trato \u00a0desigual \u00a0que \u00a0impone \u00a0corregir \u00a0la inequidad, con mayor raz\u00f3n si en virtud del \u00a0principio \u00a0de \u00a0proporcionalidad \u00a0de \u00a0la pena, el delito cuya permanencia se haya \u00a0extendido \u00a0m\u00e1s \u00a0en \u00a0el tiempo debe tener una sanci\u00f3n superior a la derivada de \u00a0un punible de duraci\u00f3n inferior. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u201cQuinta, \u00a0si uno de los prop\u00f3sitos de la lex previa se orienta a \u00a0cumplir \u00a0con \u00a0la \u00a0funci\u00f3n de prevenci\u00f3n general de la pena, en el entendido de \u00a0que \u00a0cuando \u00a0el \u00a0legislador \u00a0dentro \u00a0de \u00a0su libertad de configuraci\u00f3n normativa \u00a0eleva \u00a0a \u00a0delito \u00a0un \u00a0determinado \u00a0comportamiento est\u00e1 enviando un mensaje a la \u00a0sociedad \u00a0para que las personas se abstengan de cometer tal conducta, so pena de \u00a0estar \u00a0llamadas \u00a0a soportar la sanci\u00f3n anunciada, no hay duda que el aumento de \u00a0punibilidad \u00a0de \u00a0un \u00a0delito \u00a0como \u00a0producto de la pol\u00edtica criminal del Estado, \u00a0supone \u00a0para \u00a0quienes \u00a0se encuentran en tal predicamento dos posibilidades: Una, \u00a0dejar \u00a0de cometer la conducta antes de que empiece a regir la nueva punibilidad, \u00a0v.g. \u00a0liberar \u00a0al plagiado en el delito de secuestro, abandonar el alzamiento en \u00a0armas \u00a0en \u00a0el \u00a0punible \u00a0de \u00a0rebeli\u00f3n, \u00a0o \u00a0dejar \u00a0el grupo acordado para cometer \u00a0delitos \u00a0en el il\u00edcito de concierto para delinquir, respondiendo \u00fanicamente de \u00a0conformidad \u00a0 con \u00a0 la \u00a0 pena \u00a0 establecida \u00a0 en \u00a0 le \u00a0 ley \u00a0 para \u00a0tal \u00a0momento \u00a0vigente. \u00a0\u00a0<\/p>\n<p>\u201cLa otra, continuar con la comisi\u00f3n del \u00a0delito \u00a0 permanente \u00a0 dentro \u00a0 de \u00a0 su \u00a0autonom\u00eda \u00a0y \u00a0posibilidad \u00a0efectiva \u00a0de \u00a0determinaci\u00f3n, \u00a0pero, \u00a0desde \u00a0luego, asumiendo los nuevos costos punitivos m\u00e1s \u00a0gravosos \u00a0dispuestos \u00a0por \u00a0el \u00a0legislador, \u00a0pues \u00a0no se aviene con una pol\u00edtica \u00a0criminal \u00a0coherente \u00a0que \u00a0el incremento de penas para los delitos permanentes ya \u00a0iniciados \u00a0no \u00a0se \u00a0traduzca \u00a0efectivamente \u00a0en \u00a0su \u00a0imposici\u00f3n, \u00a0con lo cual se \u00a0estimular\u00eda \u00a0la \u00a0prolongaci\u00f3n \u00a0en \u00a0el \u00a0tiempo \u00a0de tales comportamientos con la \u00a0correlativa \u00a0afrenta \u00a0persistente \u00a0para \u00a0el \u00a0bien \u00a0jur\u00eddico \u00a0objeto \u00a0de tutela. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cA \u00a0manera de ejemplo dest\u00e1quese que si \u00a0una \u00a0persona \u00a0tiene en su poder determinada sustancia, cuya tenencia a partir de \u00a0cierta \u00a0fecha \u00a0futura \u00a0ser\u00e1 \u00a0punible \u00a0al \u00a0ser \u00a0incluida como precursora para el \u00a0procesamiento \u00a0de \u00a0estupefacientes, \u00a0esa \u00a0tenencia l\u00edcita inicial no la faculta \u00a0para \u00a0continuar con la sustancia una vez entre en vigencia la prohibici\u00f3n, pues \u00a0por \u00a0el \u00a0contrario, \u00a0est\u00e1 llamada a deshacerse de tal producto para no incurrir \u00a0en \u00a0la \u00a0comisi\u00f3n \u00a0del \u00a0delito, y obviamente, de no proceder a ello, esa inicial \u00a0licitud \u00a0 no \u00a0 tiene \u00a0 la \u00a0 virtud \u00a0de \u00a0volver \u00a0tambi\u00e9n \u00a0l\u00edcita \u00a0la \u00a0fase \u00a0del \u00a0comportamiento \u00a0permanente \u00a0cometida bajo el imperio de la nueva legislaci\u00f3n, y \u00a0por \u00a0 \u00a0tanto, \u00a0 \u00a0se \u00a0 \u00a0har\u00e1 \u00a0 \u00a0acreedora \u00a0 a \u00a0 la \u00a0 condigna \u00a0 pena\u201d. \u00a0\u00a0<\/p>\n<p>En tales condiciones, como se anunci\u00f3, el \u00a0libelo se inadmitir\u00e1. \u00a0\u00a0<\/p>\n<p>Resta \u00a0se\u00f1alar \u00a0que no se observa que con \u00a0ocasi\u00f3n \u00a0de la sentencia impugnada dentro de la actuaci\u00f3n se violaran derechos \u00a0o \u00a0garant\u00edas \u00a0de \u00a0los \u00a0intervinientes, \u00a0como para que tal circunstancia imponga \u00a0superar \u00a0los \u00a0defectos \u00a0del \u00a0libelo \u00a0para decidir de fondo, seg\u00fan lo dispone el \u00a0art\u00edculo 216 de la Ley 600 de 2000. \u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la CORTE \u00a0SUPREMA \u00a0DE JUSTICIA, SALA DE CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>R E S U E L V E \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0INADMITIR \u00a0 la \u00a0 demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0por \u00a0el defensor \u00a0de \u00a0Diomedes \u00a0Rafael \u00a0S\u00e1nchez \u00a0De Castro. \u00a0\u00a0<\/p>\n<p>Contra \u00a0la \u00a0anterior \u00a0decisi\u00f3n no procede \u00a0ning\u00fan recurso. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0 comun\u00edquese \u00a0 y \u00a0c\u00famplase. \u00a0Devu\u00e9lvase al Tribunal de origen. \u00a0\u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0<\/p>\n<p>JOS\u00c9 \u00a0LUIS \u00a0BARCEL\u00d3 CAMACHO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0FERNANDO ALBERTO CASTRO CABALLERO \u00a0\u00a0<\/p>\n<p>MAR\u00cdA \u00a0 \u00a0DEL \u00a0 \u00a0ROSARIO \u00a0 \u00a0GONZ\u00c1LEZ \u00a0MU\u00d1OZ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0GUSTAVO \u00a0E.\u00a0 MALO FERN\u00c1NDEZ \u00a0\u00a0<\/p>\n<p>LUIS \u00a0GUILLERMO \u00a0SALAZAR OTERO \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JULIO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ENRIQUE \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 SOCHA \u00a0SALAMANCA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JAVIER\u00a0 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 \u00a0ZAPATA \u00a0ORTIZ \u00a0\u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA \u00a0 DE \u00a0 CASACI\u00d3N \u00a0PENAL \u00a0\u00a0 Magistrado \u00a0Ponente \u00a0\u00a0 FERNANDO ALBERTO CASTRO CABALLERO \u00a0 Aprobado \u00a0acta N\u00ba \u00a0436 \u00a0\u00a0 Bogot\u00e1 \u00a0D.C., \u00a0veintiocho de noviembre de dos mil doce (2012). \u00a0\u00a0 V \u00a0 I \u00a0 S \u00a0 T \u00a0 O \u00a0S \u00a0\u00a0 La \u00a0Sala \u00a0resuelve \u00a0la \u00a0admisibilidad de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-25297","post","type-post","status-publish","format-standard","hentry","category-20"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/25297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=25297"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/25297\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=25297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=25297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=25297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}