{"id":2437,"date":"2023-09-07T21:28:39","date_gmt":"2023-09-07T21:28:39","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/07\/16036j\/"},"modified":"2023-09-07T21:28:39","modified_gmt":"2023-09-07T21:28:39","slug":"16036j","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/07\/16036j\/","title":{"rendered":"16036j"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No. 16036 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CORTE SUPREMA DE JUSTICIA \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0SALA DE CASACION PENAL \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 Magistrado \u00a0Ponente: \u00a0\u00a0<\/p>\n<p>Dr. CARLOS AUGUSTO GALVEZ ARGOTE \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Aprobado \u00a0Acta No. 116. \u00a0\u00a0<\/p>\n<p>Santaf\u00e9 \u00a0de \u00a0Bogot\u00e1, \u00a0D.C., \u00a0cinco \u00a0(5) de \u00a0agosto de mil novecientos noventa y nueve (1.999). \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0VISTOS: \u00a0\u00a0<\/p>\n<p>Se \u00a0pronuncia \u00a0la \u00a0Sala \u00a0sobre el recurso de \u00a0hecho \u00a0interpuesto \u00a0por \u00a0el \u00a0defensor del procesado en contra de la decisi\u00f3n de \u00a0junio \u00a03 \u00a0del \u00a0a\u00f1o \u00a0en \u00a0curso \u00a0por medio de la cual el Tribunal Superior de San \u00a0Andr\u00e9s deneg\u00f3 el de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>ANTECEDENTES: \u00a0<\/p>\n<p>Acusado \u00a0EDGAR \u00a0SINCLAIRE \u00a0CHRISTOPHER \u00a0por \u00a0infracci\u00f3n \u00a0al \u00a0art\u00edculo 33 de la Ley 30 de 1.986 y adelantado en su contra el \u00a0correspondiente \u00a0juicio \u00a0concluy\u00f3 \u00a0\u00e9ste \u00a0con \u00a0sentencia \u00a0de \u00a0marzo \u00a0de 1.999 a \u00a0trav\u00e9s \u00a0de \u00a0la \u00a0cual \u00a0el \u00a0Juzgado \u00a0Primero Penal del Circuito de San Andr\u00e9s lo \u00a0conden\u00f3 \u00a0por \u00a0el \u00a0citado \u00a0delito \u00a0a \u00a0pena \u00a0privativa \u00a0de \u00a0libertad \u00a0de 4 a\u00f1os, \u00a0confirmada \u00a0por \u00a0el Tribunal Superior de ese Distrito Judicial en fallo de abril \u00a022 \u00a0del a\u00f1o en curso siendo \u00e9ste notificado personalmente al procesado el d\u00eda \u00a023 \u00a0siguiente, \u00a0al \u00a0defensor el 27 y al Ministerio P\u00fablico el 30 del mismo mes, \u00a0surti\u00e9ndose \u00a0tal acto respecto de los dem\u00e1s sujetos procesales mediante edicto \u00a0que \u00a0permaneci\u00f3 \u00a0fijado \u00a0entre \u00a0el \u00a029 \u00a0de \u00a0abril y el 3 de mayo de la presente \u00a0anualidad. \u00a0\u00a0<\/p>\n<p>El \u00a03 \u00a0de junio siguiente y ante escrito del \u00a0defensor \u00a0presentado el 28 de mayo en el que manifest\u00f3 recurrir en casaci\u00f3n la \u00a0sentencia \u00a0dictada \u00a0por \u00a0el \u00a0Juzgado \u00a0Primero \u00a0Penal \u00a0del Circuito, \u201cratificada \u00a0 \u00a0por \u00a0 esa \u00a0 Honorable \u00a0Corporaci\u00f3n \u00a0 el \u00a0d\u00eda \u00a022 \u00a0de \u00a0abril\u201d, \u00a0 el \u00a0 Tribunal \u00a0 dict\u00f3 \u00a0 auto \u00a0absteni\u00e9ndose \u00a0de \u00a0conceder \u00a0la \u00a0impugnaci\u00f3n \u00a0 extraordinaria \u00a0porque \u00a0adem\u00e1s \u00a0de \u00a0ser \u00a0improcedente \u00a0frente \u00a0a \u00a0sentencias \u00a0de \u00a0primera instancia fue formulada de manera extempor\u00e1nea toda vez \u00a0que \u00a0el memorial respectivo se present\u00f3 18 d\u00edas despu\u00e9s de surtida la \u00faltima \u00a0notificaci\u00f3n de la sentencia. \u00a0\u00a0<\/p>\n<p>Contra \u00a0dicha negativa el defensor interpuso \u00a0el \u00a0recurso de hecho, sustent\u00e1ndolo dentro del t\u00e9rmino para ello, argumentando \u00a0que \u00a0si bien pudo haberse equivocado al expresar que propon\u00eda el recurso contra \u00a0la \u00a0sentencia \u00a0de \u00a0primera \u00a0instancia, \u00a0no \u00a0menos \u00a0cierto \u00a0es \u00a0que tambi\u00e9n hizo \u00a0menci\u00f3n \u00a0de \u00a0la \u00a0providencia \u00a0del \u00a022 de abril entendiendo que as\u00ed se refer\u00eda \u00a0igualmente a la proferida por el ad quem. \u00a0\u00a0<\/p>\n<p>Agrega, \u00a0 \u00a0aludiendo \u00a0 \u00a0al \u00a0 juicio \u00a0 de \u00a0extemporaneidad \u00a0con \u00a0que \u00a0se \u00a0le \u00a0neg\u00f3 \u00a0el \u00a0recurso, que habi\u00e9ndose fijado el \u00a0estado, \u00a0que no el edicto como equivocadamente lo afirma el Tribunal, el d\u00eda 29 \u00a0de \u00a0abril y notificado personalmente el agente del Ministerio P\u00fablico el 30 del \u00a0mismo \u00a0mes, \u00a0s\u00f3lo \u00a0a \u00a0partir \u00a0del \u00a0d\u00eda \u00a0siguiente, \u00a0o \u00a0sea \u00a0del \u00a03 de mayo, de \u00a0conformidad \u00a0con \u00a0los \u00a0art\u00edculos \u00a0188 y 190 del C\u00f3digo de Procedimiento Penal, \u00a0empezar\u00edan \u00a0a \u00a0transcurrir los t\u00e9rminos, todo lo cual significa, en su sentir, \u00a0que \u00a0la \u00a0impugnaci\u00f3n extraordinaria debi\u00f3 conced\u00e9rsele, como as\u00ed lo solicita \u00a0a trav\u00e9s del recurso de hecho. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0CONSIDERACIONES: \u00a0\u00a0<\/p>\n<p>1. Denegado que fuera el recurso de casaci\u00f3n \u00a0por \u00a0el \u00a0ad \u00a0quem sustent\u00e1ndose para ello en un argumento de procedencia y otro \u00a0de \u00a0oportunidad, \u00a0no \u00a0obstante carecer de fundamento el primero, encu\u00e9ntrase de \u00a0todas \u00a0maneras \u00a0correcta \u00a0la \u00a0negativa \u00a0a \u00a0conceder \u00a0el \u00a0extraordinario medio de \u00a0impugnaci\u00f3n. \u00a0\u00a0<\/p>\n<p>2. \u00a0En \u00a0efecto, si bien el art\u00edculo 218 del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0establece \u00a0inequ\u00edvocamente \u00a0que la casaci\u00f3n \u00a0procede \u00a0contra \u00a0sentencias \u00a0de \u00a0segunda instancia proferidas por los Tribunales \u00a0que \u00a0all\u00ed \u00a0se \u00a0indican, \u00a0la \u00a0inapropiada redacci\u00f3n exhibida por el defensor al \u00a0interponer \u00a0tal \u00a0recurso \u00a0no \u00a0es \u00a0causa \u00a0suficiente para adoptar la decisi\u00f3n de \u00a0negarlo \u00a0pues \u00a0no \u00a0se\u00f1alando \u00a0nuestro ordenamiento norma sacramental alguna, se \u00a0tiene \u00a0por \u00a0comprendido \u00a0en \u00a0la \u00a0misma \u00a0ley \u00a0que \u00a0tal \u00a0medio \u00a0extraordinario \u00a0de \u00a0impugnaci\u00f3n, \u00a0sea \u00a0el \u00a0com\u00fan \u00a0o \u00a0el excepcional, s\u00f3lo resulta viable frente a \u00a0fallos dictados por el ad quem. \u00a0\u00a0<\/p>\n<p>3. \u00a0No \u00a0obstante \u00a0que \u00a0en \u00a0los \u00a0anteriores \u00a0t\u00e9rminos \u00a0el \u00a0argumento \u00a0referido \u00a0a la procedencia resulta infundado, no puede \u00a0sostenerse \u00a0id\u00e9ntica conclusi\u00f3n frente al de extemporaneidad del cual tambi\u00e9n \u00a0se vali\u00f3 el ad quem para no conceder la casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>En \u00a0primer \u00a0t\u00e9rmino, \u00a0como \u00a0se trata de una \u00a0sentencia, \u00a0la referencia que el recurrente hace al art\u00edculo 190 del C\u00f3digo de \u00a0Procedimiento \u00a0Penal \u00a0deviene desacertada en la medida en que no regulando dicho \u00a0ordenamiento \u00a0las \u00a0notificaciones \u00a0por \u00a0edicto \u00a0ha \u00a0de aplicarse la normatividad \u00a0procesal \u00a0civil, \u00a0donde \u00a0es \u00a0claro \u00a0(Art\u00edculo \u00a0323) \u00a0que \u00a0los \u00a0fallos que no se \u00a0hubieren \u00a0notificado \u00a0personalmente se har\u00e1n saber por tal medio que se fijar\u00e1 \u00a0por \u00a0el \u00a0t\u00e9rmino \u00a0de tres d\u00edas y por ende concl\u00fayese equivocada igualmente la \u00a0alusi\u00f3n \u00a0a \u00a0la notificaci\u00f3n por estado a que se refiere el defensor, cuando es \u00a0indudable \u00a0que \u00a0en \u00a0este \u00a0asunto \u00a0el Tribunal procedi\u00f3 a comunicar por edicto a \u00a0aquellos \u00a0sujetos \u00a0procesales que no se notificaron personalmente, no existiendo \u00a0tampoco \u00a0obligaci\u00f3n \u00a0legal \u00a0de \u00a0hacerlo, como s\u00ed la existe en relaci\u00f3n con el \u00a0procesado privado de libertad y el Ministerio P\u00fablico. \u00a0\u00a0<\/p>\n<p>Es \u00a0que, \u00a0la \u00a0fijaci\u00f3n \u00a0del \u00a0edicto \u00a0suple \u00a0solamente \u00a0la \u00a0notificaci\u00f3n \u00a0a \u00a0aquellos \u00a0sujetos \u00a0procesales \u00a0a \u00a0quienes no es \u00a0imperativo \u00a0legal hacerles saber personalmente el fallo, mas no as\u00ed respecto de \u00a0quienes \u00a0s\u00ed \u00a0existe \u00a0dicha \u00a0exigencia; es decir que no relevando aquel medio al \u00a0funcionario \u00a0de \u00a0cumplir \u00a0con \u00a0esa \u00a0carga inane resulta pretender un determinado \u00a0orden \u00a0en las comunicaciones que conlleve a efectuar las personales obligatorias \u00a0antes del edicto. \u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0 las \u00a0 cosas, \u00a0 si \u00a0 por \u00a0 cualquier \u00a0circunstancia \u00a0no \u00a0es \u00a0posible \u00a0la \u00a0notificaci\u00f3n \u00a0personal \u00a0de \u00a0la sentencia al \u00a0procesado \u00a0privado de libertad y al Ministerio P\u00fablico dentro de los tres d\u00edas \u00a0siguientes \u00a0a \u00a0su \u00a0fecha \u00a0eso \u00a0no \u00a0impide \u00a0que \u00a0se realice por edicto a aquellos \u00a0sujetos \u00a0procesales \u00a0a \u00a0quienes no es obligatorio comunic\u00e1rsela personalmente y \u00a0que \u00a0luego \u00a0o simult\u00e1neamente se proceda a aquella, pues respecto de \u00e9stos s\u00ed \u00a0existe \u00a0el \u00a0medio \u00a0suced\u00e1neo \u00a0que \u00a0no \u00a0puede \u00a0aplicarse \u00a0en \u00a0relaci\u00f3n \u00a0con los \u00a0primeros. \u00a0\u00a0<\/p>\n<p>En \u00a0 consecuencia, \u00a0bien \u00a0que \u00a0la \u00a0\u00faltima \u00a0notificaci\u00f3n \u00a0sea \u00a0la \u00a0personal a los sujetos a que se refiere el art\u00edculo 189 \u00a0del \u00a0C\u00f3digo \u00a0de Procedimiento Penal o la efectuada mediante edicto es lo cierto \u00a0que \u00a0el t\u00e9rmino de 15 d\u00edas para interponer el recurso de casaci\u00f3n se cuenta a \u00a0partir \u00a0del \u00a0d\u00eda \u00a0siguiente \u00a0de \u00a0sucedida aquella, m\u00e1xime que el art\u00edculo 223 \u00a0\u00eddem \u00a0no establece ninguna distinci\u00f3n sobre la naturaleza del acto procesal de \u00a0comunicaci\u00f3n, \u00a0condicionando el inicio de la oportunidad solamente a que sea la \u00a0\u201c\u00faltima \u00a0notificaci\u00f3n\u201d. \u00a0\u00a0<\/p>\n<p>4. \u00a0Como \u00a0en \u00a0este \u00a0asunto \u00a0esa \u201c\u00faltima \u00a0 notificaci\u00f3n\u201d de la sentencia de segunda instancia \u00a0corresponde \u00a0a \u00a0la realizada mediante edicto fijado del 29 de abril al 3 de mayo \u00a0del \u00a0a\u00f1o \u00a0en \u00a0curso, habi\u00e9ndose efectuado las personales al procesado detenido \u00a0en \u00a0abril 23 y al Ministerio P\u00fablico el d\u00eda 30 del mismo mes, significa que el \u00a0referido \u00a0t\u00e9rmino \u00a0para interponer la casaci\u00f3n transcurri\u00f3 entre el 4 y el 25 \u00a0de \u00a0mayo del presente a\u00f1o y que, por consiguiente, la impugnaci\u00f3n del defensor \u00a0del \u00a0procesado fue efectivamente extempor\u00e1nea por haber sido presentado el d\u00eda \u00a028 \u00a0de \u00a0dicho \u00a0mes, \u00a0todo \u00a0lo cual conduce a la Sala a declarar bien denegado el \u00a0recurso \u00a0extraordinario \u00a0interpuesto \u00a0en \u00a0nombre \u00a0del \u00a0acusado \u00a0y \u00a0a \u00a0ordenar la \u00a0remisi\u00f3n \u00a0de \u00a0esta actuaci\u00f3n al inferior para que de conformidad con el inciso \u00a01\u00ba \u00a0del \u00a0art\u00edculo \u00a0210 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0haga parte del \u00a0expediente. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, LA CORTE SUPREMA \u00a0DE JUSTICIA, \u00a0\u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL, \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0RESUELVE: \u00a0\u00a0<\/p>\n<p>DECLARAR correctamente denegado el recurso de \u00a0casaci\u00f3n \u00a0interpuesto por el defensor del procesado EDGAR SINCLAIRE CHRISTOPHER \u00a0contra \u00a0la \u00a0sentencia \u00a0proferida \u00a0en \u00a0abril 22 del a\u00f1o en curso por el Tribunal \u00a0Superior de San Andr\u00e9s, Providencia y Santa Catalina. \u00a0\u00a0<\/p>\n<p>Rem\u00edtase la presente actuaci\u00f3n al inferior \u00a0a fin de que haga parte del expediente. \u00a0\u00a0<\/p>\n<p>COPIESE, NOTIFIQUESE Y CUMPLASE. \u00a0<\/p>\n<p>JORGE ANIBAL GOMEZ GALLEGO \u00a0<\/p>\n<p>FERNANDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ARBOLEDA \u00a0RIPOLL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JORGE \u00a0E. \u00a0CORDOBA \u00a0POVEDA\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0 \u00a0 \u00a0 AUGUSTO \u00a0 \u00a0 \u00a0 GALVEZ \u00a0ARGOTE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 EDGAR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 LOMBANA \u00a0TRUJILLO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>MARIO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 MANTILLA \u00a0NOUGUES\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0CARLOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0E. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 MEJIA \u00a0ESCOBAR\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>ALVARO \u00a0 \u00a0 \u00a0 ORLANDO \u00a0 \u00a0 \u00a0 PEREZ \u00a0PINZON\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0NILSON \u00a0 \u00a0 \u00a0 \u00a0 PINILLA \u00a0PINILLA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>PATRICIA SALAZAR CUELLAR \u00a0<\/p>\n<p>SECRETARIA \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No. 16036 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CORTE SUPREMA DE JUSTICIA \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0SALA DE CASACION PENAL \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 Magistrado \u00a0Ponente: \u00a0\u00a0 Dr. CARLOS AUGUSTO GALVEZ ARGOTE \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2437","post","type-post","status-publish","format-standard","hentry","category-7"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/2437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=2437"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/2437\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=2437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=2437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=2437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}