{"id":24223,"date":"2023-09-12T17:21:39","date_gmt":"2023-09-12T17:21:39","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3795218-04-12\/"},"modified":"2023-09-12T17:21:39","modified_gmt":"2023-09-12T17:21:39","slug":"3795218-04-12","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3795218-04-12\/","title":{"rendered":"37952(18-04-12)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso n\u00ba 37952 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrada Ponente: \u00a0<\/p>\n<p>MARIA \u00a0DEL \u00a0ROSARIO \u00a0GONZ\u00c1LEZ \u00a0MU\u00d1OZ Aprobado Acta No. 139. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D. \u00a0C., abril dieciocho (18) de dos \u00a0mil doce (2012). \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Se pronuncia la Corte sobre la admisibilidad \u00a0de \u00a0la \u00a0demanda \u00a0presentada \u00a0por \u00a0el defensor de JHONY \u00a0PARDO \u00a0DUARTE \u00a0con \u00a0el \u00a0objeto de sustentar el recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n interpuesto contra la sentencia proferida el 30 de \u00a0septiembre \u00a0de \u00a02011, \u00a0a \u00a0trav\u00e9s \u00a0de \u00a0la \u00a0cual \u00a0el Tribunal Superior de San Gil \u00a0confirm\u00f3 \u00a0la \u00a0dictada \u00a0el 14 de julio anterior por el Juzgado Primero Penal del \u00a0Circuito \u00a0de \u00a0V\u00e9lez \u00a0que \u00a0conden\u00f3 \u00a0al \u00a0mencionado \u00a0por \u00a0el delito de homicidio \u00a0agravado. \u00a0\u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>Los \u00a0 \u00a0sintetiz\u00f3 \u00a0 \u00a0el \u00a0 \u00a0ad-quem, \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 la \u00a0 \u00a0 siguiente \u00a0manera: \u00a0\u00a0<\/p>\n<p>\u201cDe lo probado en el juicio oral se extrae \u00a0que \u00a0JHONY \u00a0PARDO \u00a0DUARTE \u00a0determin\u00f3 \u00a0mediante amenazas e intimidaci\u00f3n a Ra\u00fal \u00a0Pe\u00f1a \u00a0 Mosquera \u00a0 para \u00a0 que \u00a0 diera \u00a0 muerte \u00a0a \u00a0la \u00a0ni\u00f1a \u00a0Y.A.V.1 \u00a0 \u00a0quien \u00a0acatando \u00a0la \u00a0orden de aqu\u00e9l, se desplaz\u00f3 el martes 1 de mayo de 2007 en horas \u00a0de \u00a0la \u00a0ma\u00f1ana \u00a0hasta \u00a0la \u00a0finca \u00a0donde \u00a0resid\u00eda la menor en compa\u00f1\u00eda de sus \u00a0padres \u00a0y \u00a0aprovechando \u00a0que \u00a0ella se encontraba sola, cuidando la leche reci\u00e9n \u00a0orde\u00f1ada \u00a0y un caballo, mientras su madre iba a ayudarle a un vecino a curar un \u00a0ternero, \u00a0la \u00a0baj\u00f3 \u00a0por \u00a0un \u00a0camino \u00a0a \u00a050 \u00a0metros \u00a0de la casa y la estrangul\u00f3 \u00a0infligi\u00e9ndole \u00a0 \u00a0tambi\u00e9n \u00a0 \u00a0una \u00a0 \u00a0herida \u00a0 \u00a0cortopunzante \u00a0 en \u00a0 la \u00a0 regi\u00f3n \u00a0cervical. \u00a0\u00a0<\/p>\n<p>PARDO DUARTE actu\u00f3 motivado por el odio que \u00a0profesaba \u00a0a \u00a0su \u00a0cu\u00f1ada \u00a0Lilia Vargas, progenitora de la v\u00edctima, en raz\u00f3n a \u00a0que \u00a0siempre \u00a0rechaz\u00f3 \u00a0las \u00a0propuestas indecorosas de tipo sexual que le ven\u00eda \u00a0haciendo \u00a0desde \u00a0el \u00a02004 \u00a0lo \u00a0que \u00a0origin\u00f3 \u00a0que \u00a0Vladimiro \u00a0Vargas, hermano de \u00a0aqu\u00e9lla, \u00a0le \u00a0hiciera el reclamo en el a\u00f1o 2006, suscit\u00e1ndose entre ellos una \u00a0ri\u00f1a \u00a0y \u00a0como consecuencia de ello una grave lesi\u00f3n en el ojo de PARDO DUARTE, \u00a0que \u00a0increment\u00f3 \u00a0el \u00a0rencor, llev\u00e1ndole a reiterar las amenazas a Lilia de que \u00a0iba \u00a0 \u00a0a \u00a0 hacerle \u00a0 algo \u00a0 que \u00a0 le \u00a0 doliera \u00a0 toda \u00a0 la \u00a0 vida\u201d.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>ANTECEDENTES \u00a0RELEVANTES \u00a0\u00a0<\/p>\n<p>Con \u00a0fundamento en los hechos anteriores se \u00a0captur\u00f3 \u00a0 \u00a0a \u00a0 \u00a0JHONY \u00a0 PARDO \u00a0 DUARTE, \u00a0 \u00a0 cuya \u00a0 \u00a0 legalizaci\u00f3n \u00a0 \u00a0 tuvo \u00a0 \u00a0lugar \u00a0 \u00a0en \u00a0 \u00a0audiencia \u00a0preliminar \u00a0celebrada \u00a0el \u00a025 de febrero de 2011 ante el \u00a0Juzgado \u00a0Tercero \u00a0Promiscuo \u00a0Municipal \u00a0de Barbosa, misma en la cual \u00a0la fiscal\u00eda formul\u00f3 imputaci\u00f3n en su \u00a0contra \u00a0 por \u00a0 el \u00a0 delito \u00a0 de \u00a0 homicidio \u00a0agravado, \u00a0delincuencia \u00a0que \u00a0el \u00a0mencionado \u00a0no \u00a0acept\u00f3 \u00a0y \u00a0por \u00a0la \u00a0que \u00a0se le \u00a0 impuso \u00a0 medida \u00a0de \u00a0aseguramiento \u00a0de \u00a0detenci\u00f3n \u00a0preventiva \u00a0intramural. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a0 6 \u00a0 de \u00a0agosto \u00a0siguiente, \u00a0la \u00a0Fiscal\u00eda \u00a0radic\u00f3 \u00a0escrito \u00a0de \u00a0acusaci\u00f3n \u00a0en \u00a0contra \u00a0del \u00a0procesado por el delito de homicidio agravado (art. \u00a0104, \u00a0nums. \u00a04 \u00a0y \u00a07 \u00a0del \u00a0C.P.), \u00a0cargo \u00a0ratificado \u00a0durante \u00a0la \u00a0audiencia \u00a0de \u00a0formulaci\u00f3n \u00a0de \u00a0acusaci\u00f3n celebrada el 13 de abril subsiguiente en el Juzgado \u00a0Primero Penal del Circuito V\u00e9lez. \u00a0\u00a0<\/p>\n<p>En \u00a0el citado despacho judicial se evacuaron \u00a0las \u00a0audiencias \u00a0preparatoria \u00a0y de juicio oral, a cuyo t\u00e9rmino, el 14 de julio \u00a0ulterior, \u00a0dict\u00f3 \u00a0fallo de primer grado mediante el cual conden\u00f3 a \u00a0JHONY PARDO DUARTE como autor penalmente \u00a0responsable \u00a0 del \u00a0 delito \u00a0 de \u00a0homicidio \u00a0agravado \u00a0a \u00a0la \u00a0pena \u00a0principal \u00a0de \u00a0cuatrocientos \u00a0ochenta \u00a0(480) meses de prisi\u00f3n y a la \u00a0accesoria \u00a0 de \u00a0inhabilitaci\u00f3n \u00a0para \u00a0el \u00a0ejercicio \u00a0de \u00a0derechos \u00a0y \u00a0funciones \u00a0p\u00fablicas \u00a0por \u00a0el \u00a0t\u00e9rmino \u00a0de \u00a020 a\u00f1os. En la misma decisi\u00f3n, el juzgado le \u00a0neg\u00f3 \u00a0el \u00a0subrogado \u00a0penal \u00a0de \u00a0la \u00a0condena \u00a0de \u00a0ejecuci\u00f3n \u00a0condicional \u00a0y \u00a0el \u00a0sustitutivo de la prisi\u00f3n domiciliaria. \u00a0\u00a0<\/p>\n<p>Contra el fallo de primer grado, PARDO \u00a0DUARTE \u00a0y su defensor interpusieron \u00a0recurso \u00a0de \u00a0apelaci\u00f3n, sobre el cual se pronunci\u00f3 el Tribunal Superior de San \u00a0Gil el 30 de septiembre de 2011, imparti\u00e9ndole confirmaci\u00f3n. \u00a0\u00a0<\/p>\n<p>En desacuerdo con la providencia anterior, el \u00a0defensor \u00a0de \u00a0PARDO \u00a0DUARTE \u00a0interpuso \u00a0recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n, \u00a0por \u00a0cuyo \u00a0motivo la demanda \u00a0presentada \u00a0con \u00a0el fin de sustentarlo se remiti\u00f3 a esta Sala, aprest\u00e1ndose al \u00a0estudio sobre su admisibilidad. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Plantea \u00a0tres \u00a0cargos. \u00a0El \u00a0primero \u00a0de \u00a0ellos \u00a0con fundamento en la \u00a0causal \u00a0segunda de casaci\u00f3n prevista en el art\u00edculo 181 de la Ley 906 de 2004, \u00a0por \u00a0afectaci\u00f3n \u00a0del \u00a0debido \u00a0proceso. \u00a0Y, los dos restantes bajo la \u00e9gida del \u00a0motivo \u00a0tercero de la misma norma, por violaci\u00f3n indirecta de la ley sustancial \u00a0derivada \u00a0de errores de hecho por falso raciocinio y falso juicio de existencia, \u00a0respectivamente. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Por \u00a0 razones \u00a0de \u00a0m\u00e9todo, \u00a0la \u00a0Corte, \u00a0en \u00a0el \u00a0siguiente \u00a0apartado \u00a0considerativo, \u00a0expondr\u00e1 \u00a0su \u00a0criterio \u00a0tan \u00a0pronto \u00a0sintetice el contenido del \u00a0cargo \u00a0de \u00a0acuerdo \u00a0con \u00a0el \u00a0orden propuesto por el libelista, evitando con ello \u00a0incurrir \u00a0en \u00a0repeticiones \u00a0innecesarias. Dicha labor, adem\u00e1s, la desarrollar\u00e1 \u00a0conjuntamente \u00a0en \u00a0lo \u00a0que \u00a0tiene \u00a0que \u00a0ver con los dos cargos sustentados en la \u00a0causal de violaci\u00f3n indirecta de la ley sustancial. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Cargo primero. Causal segunda, nulidad por \u00a0desconocimiento del debido proceso. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Se\u00f1ala \u00a0el \u00a0censor que \u201cla sentencia de \u00a0segunda \u00a0instancia viol\u00f3 de manera directa la ley sustancial, art\u00edculo 28, 29, \u00a033 \u00a0 (sic) \u00a0 Constituci\u00f3n \u00a0Pol\u00edtica; \u00a0art\u00edculos \u00a01, \u00a02, \u00a08, \u00a023, \u00a0267, 282 (sic) \u00a0del \u00a0C\u00f3digo \u00a0de Procedimiento Penal ley 906 de 2004, \u00a0puesto \u00a0que \u00a0en \u00a0el \u00a0presente proceso se vulneraron las garant\u00edas fundamentales \u00a0del \u00a0se\u00f1or \u00a0Ra\u00fal Pe\u00f1a Mosquera y del se\u00f1or JHONY PARDO DUARTE, que afectaron \u00a0el \u00a0 \u00a0 \u00a0debido \u00a0 \u00a0 \u00a0proceso \u00a0 \u00a0 \u00a0constitucional \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 \u00a0legal\u201d.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Seg\u00fan \u00a0el \u00a0censor, \u00a0se \u00a0configur\u00f3 la transgresi\u00f3n de los derechos \u00a0referidos \u00a0del \u00a0primero \u00a0en \u00a0cita \u00a0desde \u00a0el \u00a0momento \u00a0mismo \u00a0en \u00a0que la se\u00f1ora \u00a0Lilia Vargas, progenitora de \u00a0la \u00a0menor \u00a0v\u00edctima \u00a0de \u00a0los hechos, lo mencion\u00f3 en su relato, adquiriendo as\u00ed \u00a0\u201cla \u00a0condici\u00f3n de indiciado con el revestimiento y \u00a0las \u00a0 garant\u00edas \u00a0 que \u00a0 consagra \u00a0la \u00a0Constituci\u00f3n \u00a0Nacional, \u00a0la \u00a0Convenci\u00f3n \u00a0Interamericana \u00a0de \u00a0Derechos \u00a0Humanos \u00a0o Pacto de San Jos\u00e9 de Costa Rica, y los \u00a0derechos \u00a0 \u00a0 que \u00a0 \u00a0 consagra \u00a0 \u00a0 la \u00a0 \u00a0 ley \u00a0 \u00a0906 \u00a0 \u00a0de \u00a0 \u00a02004\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Acto \u00a0seguido \u00a0se\u00f1ala que, como este mismo implicado lo manifest\u00f3, \u00a0fue \u00a0apeado, \u00a0sin \u00a0orden \u00a0judicial, \u00a0de \u00a0un veh\u00edculo de transporte p\u00fablico por \u00a0funcionarios \u00a0de \u00a0Polic\u00eda \u00a0Judicial, \u00a0quienes \u00a0lo \u00a0condujeron \u00a0al \u00a0municipio de \u00a0V\u00e9lez, \u00a0 en \u00a0donde, \u00a0el \u00a03 \u00a0de \u00a0mayo \u00a0de \u00a02007, \u00a0rindi\u00f3 \u00a0un \u00a0interrogatorio \u00a0o \u00a0declaraci\u00f3n \u00a0 \u00a0\u201cen \u00a0 \u00a0la \u00a0 \u00a0cual \u00a0 confes\u00f3 \u00a0 el \u00a0delito&#8221;. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0dicha \u00a0diligencia, agrega, Ra\u00fal Pe\u00f1a \u00a0Mosquera \u00a0fue asistido por un profesional del derecho, \u00a0cuya \u00a0actuaci\u00f3n \u00a0fue \u00a0pasiva \u00a0y \u00a0s\u00f3lo \u00a0sirvi\u00f3 \u00a0para \u00a0avalar \u00a0el \u00a0acto ilegal, \u00a0viol\u00e1ndose \u00a0as\u00ed \u00a0sus \u00a0derechos \u00a0de dignidad, debida defensa t\u00e9cnica y no auto \u00a0incriminaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Luego \u00a0 pregona \u00a0 que \u00a0tambi\u00e9n \u00a0fueron \u00a0vulneradas \u00a0las \u00a0garant\u00edas \u00a0fundamentales \u00a0 \u00a0 de \u00a0 \u00a0 su \u00a0 \u00a0 defendido \u00a0 \u00a0 PARDO \u00a0DUARTE, \u00a0\u201ca partir del 30 \u00a0de \u00a0julio \u00a0de 2007, donde soterradamente y a espaldas empezaron a contaminar y a \u00a0manipular \u00a0al \u00a0se\u00f1or Ra\u00fal Pe\u00f1a Mosquera, hasta lograr que el d\u00eda 30 de julio \u00a0de \u00a02007 \u00a0sin \u00a0existir raz\u00f3n ni motivo, ni tampoco evidencia f\u00edsica involucrar \u00a0(sic) \u00a0al se\u00f1or JHONY PARDO \u00a0DUARTE\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0De \u00a0esa forma, a\u00f1ade, a su prohijado se le desconoci\u00f3 su derecho a \u00a0la \u00a0defensa \u00a0puesto \u00a0que, \u00a0contrariando \u00a0la \u00a0sentencia\u00a0 C-029 de 2009 de la \u00a0Corte \u00a0 \u00a0Constitucional, \u00a0 \u201cdurante \u00a0 tres \u00a0 a\u00f1os \u00a0estuvieron \u00a0investigando \u00a0y \u00a0hurgando \u00a0su \u00a0responsabilidad penal, sin permitirle \u00a0ejercer \u00a0el \u00a0derecho \u00a0fundamental \u00a0a \u00a0la \u00a0defensa \u00a0y contradicci\u00f3n respecto del \u00a0testimonio \u00a0 \u00a0 \u00a0del \u00a0 \u00a0 \u00a0se\u00f1or \u00a0 \u00a0 \u00a0Ra\u00fal \u00a0 \u00a0 Pe\u00f1a \u00a0 \u00a0 Mosquera\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Ha \u00a0 debido \u00a0la \u00a0Fiscal\u00eda, \u00a0por \u00a0tanto, \u00a0informarle \u00a0acerca \u00a0de \u00a0la \u00a0pr\u00e1ctica \u00a0de \u00a0pruebas, pues, conforme la misma decisi\u00f3n, el derecho de defensa \u00a0se puede ejercer antes de la imputaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0anterior, colige que a \u201cRa\u00fal \u00a0Pe\u00f1a \u00a0Mosquera \u00a0y JHONY PARDO DUARTE en aras de buscar a \u00a0los \u00a0 \u00a0presuntos \u00a0 responsables, \u00a0 y \u00a0 no \u00a0 de \u00a0 buscar \u00a0 la \u00a0 verdad \u00a0 de \u00a0 los \u00a0hechos\u201d, se les vulneraron \u00a0las \u00a0 garant\u00edas \u00a0 referidas \u00a0 en \u00a0las \u00a0disposiciones \u00a0mencionadas \u00a0 \u201chechos \u00a0que \u00a0no \u00a0son \u00a0sutiles, \u00a0sino \u00a0constitucionales \u00a0y \u00a0flagrantes\u201d, debiendo declararse \u00a0la \u00a0 nulidad \u00a0 de \u00a0la \u00a0actuaci\u00f3n \u00a0procesal, \u00a0frente \u00a0al \u00a0primero, \u00a0\u201ca \u00a0 partir \u00a0 del \u00a0 interrogatorio \u00a0 a \u00a0 indiciado \u00a0 (sic)\u2026el \u00a0 \u00a0d\u00eda \u00a0 3 \u00a0 de \u00a0 mayo \u00a0 de \u00a02007\u201d \u00a0 y, \u00a0 respecto \u00a0 del \u00a0 segundo \u00a0\u201ca \u00a0partir \u00a0de la formulaci\u00f3n de imputaci\u00f3n\u2026realizada el d\u00eda \u00a025 de febrero del a\u00f1o 2011\u201d. \u00a0\u00a0<\/p>\n<p>Consideraciones de la Sala: \u00a0<\/p>\n<p>Ha sido insistente la Sala en se\u00f1alar que si \u00a0bien \u00a0la \u00a0propuesta \u00a0de \u00a0nulidad \u00a0en casaci\u00f3n goza de cierta flexibilidad en su \u00a0formulaci\u00f3n, \u00a0 no \u00a0por \u00a0ello \u00a0puede \u00a0prescindir \u00a0del \u00a0cumplimiento \u00a0de \u00a0algunos \u00a0requisitos para que se entienda debidamente satisfecha. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>De ese modo se ha dicho que, como m\u00ednimo, y \u00a0para \u00a0cumplir \u00a0con los presupuestos de admisi\u00f3n relativos a la presentaci\u00f3n de \u00a0una \u00a0censura \u00a0l\u00f3gica \u00a0y debidamente argumentada, es preciso que el casacionista \u00a0identifique \u00a0claramente el motivo sobre el cual gira la irregularidad propuesta, \u00a0la \u00a0causal \u00a0de \u00a0nulidad que procede como consecuencia de ese defecto, las normas \u00a0que \u00a0apoyan \u00a0su pretensi\u00f3n, la trascendencia que genera, bien en el marco de la \u00a0estructura \u00a0del \u00a0proceso \u00a0o \u00a0en \u00a0el \u00a0de las garant\u00edas fundamentales de quien la \u00a0invoca, \u00a0y \u00a0el \u00a0momento \u00a0procesal \u00a0a \u00a0partir \u00a0del \u00a0cual \u00a0se \u00a0debe \u00a0invalidar \u00a0la \u00a0actuaci\u00f3n, \u00a0as\u00ed \u00a0como \u00a0la \u00a0autoridad \u00a0judicial a la cual corresponde su env\u00edo \u00a0para que proceda a su enmienda. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Aunado \u00a0a \u00a0ello, \u00a0la \u00a0pretensi\u00f3n \u00a0debe \u00a0ce\u00f1irse \u00a0a \u00a0los principios \u00a0orientadores \u00a0de \u00a0la \u00a0declaratoria \u00a0de \u00a0las \u00a0nulidades, \u00a0a \u00a0saber, \u00a0taxatividad, \u00a0instrumentalidad \u00a0de \u00a0las \u00a0formas, \u00a0trascendencia, \u00a0protecci\u00f3n, convalidaci\u00f3n, \u00a0residualidad \u00a0 \u00a0 \u00a0 \u00a0 y \u00a0 \u00a0 \u00a0 \u00a0 acreditaci\u00f3n2. \u00a0\u00a0<\/p>\n<p>Lo \u00a0anterior, \u00a0se \u00a0insiste, \u00a0am\u00e9n \u00a0de \u00a0que \u00a0los \u00a0cargos de la demanda de casaci\u00f3n se expongan de \u00a0manera \u00a0 l\u00f3gica \u00a0y \u00a0con \u00a0un \u00a0m\u00ednimo \u00a0de \u00a0argumentaci\u00f3n \u00a0adecuada. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Pues \u00a0bien, \u00a0para \u00a0la Sala refulge evidente que la censura, tal como \u00a0se plantea, se debe inadmitir, por las siguientes razones: \u00a0\u00a0<\/p>\n<p>En \u00a0 primer \u00a0 lugar, \u00a0 por \u00a0 arrogarse \u00a0el \u00a0casacionista \u00a0la \u00a0defensa \u00a0de \u00a0derechos \u00a0que \u00a0no \u00a0representa, como ocurre con la \u00a0situaci\u00f3n \u00a0 de \u00a0 Ra\u00fal \u00a0Pe\u00f1a \u00a0Mosquera, \u00a0respecto \u00a0de \u00a0quien \u00a0eleva, \u00a0incluso, \u00a0una \u00a0petici\u00f3n concreta de \u00a0declaratoria \u00a0de \u00a0nulidad, mayormente inadmisible a\u00fan si en cuenta se tiene que \u00a0su \u00a0responsabilidad, \u00a0como autor material del delito por el cual se procede, fue \u00a0objeto \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0investigaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0tramitada \u00a0 \u00a0 \u00a0 \u00a0bajo \u00a0 \u00a0 \u00a0 cuerda \u00a0independiente.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Por \u00a0tanto, no incumbe a la Sala ocuparse de \u00a0la \u00a0responsabilidad \u00a0penal \u00a0de \u00a0dicho \u00a0individuo, cuya \u00fanica referencia v\u00e1lida \u00a0ser\u00eda \u00a0la \u00a0de \u00a0auscultar sobre los t\u00e9rminos de la delaci\u00f3n que hizo en contra \u00a0de JHONY PARDO DUARTE,\u00a0 \u00a0\u00fanico \u00a0procesado en esta actuaci\u00f3n, y ello, vale decir, en la medida en que la \u00a0propuesta \u00a0cumpla \u00a0los presupuestos de argumentaci\u00f3n y l\u00f3gica exigidos en esta \u00a0sede. \u00a0\u00a0<\/p>\n<p>Empero, \u00a0 \u00a0el \u00a0 \u00a0censor \u00a0 construye \u00a0 un \u00a0cuestionamiento \u00a0 basado \u00a0en \u00a0premisas \u00a0especulativas \u00a0y \u00a0por \u00a0fuera \u00a0del \u00a0marco \u00a0probatorio \u00a0analizado \u00a0en \u00a0los fallos, conforme al cual la delaci\u00f3n se ajusta a \u00a0la \u00a0realidad \u00a0en \u00a0tanto \u00a0obran \u00a0elementos \u00a0de \u00a0juicio \u00a0adicionales, de car\u00e1cter \u00a0indiciario, \u00a0que \u00a0as\u00ed \u00a0la confirman y que el casacionista se sustrajo a abordar \u00a0en \u00a0 \u00a0esta \u00a0 \u00a0censura, \u00a0 \u00a0ante \u00a0 \u00a0lo \u00a0 \u00a0cual \u00a0 \u00a0surge \u00a0 \u00a0evidente \u00a0 \u00a0su \u00a0 \u00a0total \u00a0intrascendencia. \u00a0\u00a0<\/p>\n<p>En segundo lugar, porque el reproche derivado \u00a0de \u00a0 no \u00a0 haber \u00a0 contado \u00a0 con \u00a0la \u00a0posibilidad \u00a0de \u00a0ejercitar \u00a0el \u00a0derecho \u00a0de \u00a0contradicci\u00f3n \u00a0 despu\u00e9s \u00a0 de \u00a0 la \u00a0 delaci\u00f3n \u00a0 del \u00a0 mencionado \u00a0Ra\u00fal \u00a0 Pe\u00f1a \u00a0Mosquera, \u00a0condenado \u00a0como \u00a0autor \u00a0material \u00a0de \u00a0los hechos, y hasta antes de que se le imputaran cargos, no \u00a0deja \u00a0de \u00a0ser \u00a0enunciativo, hasta el punto de que, incluso, omite individualizar \u00a0los \u00a0 elementos \u00a0 materiales \u00a0probatorios \u00a0acopiados \u00a0durante \u00a0ese \u00a0interregno \u00a0 y \u00a0la \u00a0forma \u00a0c\u00f3mo \u00a0fueron \u00a0determinantes \u00a0 \u00a0 para \u00a0 \u00a0 inferir \u00a0 \u00a0su \u00a0 \u00a0responsabilidad \u00a0 \u00a0en \u00a0 \u00a0el \u00a0 \u00a0fallo \u00a0impugnado. \u00a0\u00a0<\/p>\n<p>Con \u00a0mayor \u00a0fuerza \u00a0se \u00a0arriba \u00a0a \u00a0la \u00a0misma \u00a0conclusi\u00f3n \u00a0de \u00a0inadmitir\u00e1 \u00a0el \u00a0reparo, \u00a0cuando \u00a0la \u00a0revisi\u00f3n objetiva de los \u00a0fallos \u00a0de \u00a0instancia permite colegir que el juicio de culpabilidad en contra de \u00a0JOHNY \u00a0PARDO \u00a0DUARTE \u00a0tuvo \u00a0asidero \u00a0en \u00a0medios \u00a0de \u00a0prueba \u00a0debidamente \u00a0aportados durante la audiencia del \u00a0juicio oral. \u00a0\u00a0<\/p>\n<p>A \u00a0manera \u00a0de \u00a0s\u00edntesis \u00a0puede \u00a0se\u00f1alarse, \u00a0entonces, \u00a0que\u00a0 \u00a0este \u00a0reparo \u00a0no \u00a0satisface \u00a0los presupuestos de admisi\u00f3n \u00a0porque, \u00a0 de \u00a0 una \u00a0 parte, \u00a0se \u00a0intercede \u00a0por \u00a0los \u00a0derechos \u00a0de \u00a0una \u00a0persona \u00a0(Ra\u00fal \u00a0Pe\u00f1a \u00a0Mosquera) no \u00a0representada \u00a0 por \u00a0 el \u00a0 actor \u00a0y \u00a0cuyo \u00a0procesamiento \u00a0se \u00a0tramit\u00f3 \u00a0de \u00a0forma \u00a0independiente \u00a0y, \u00a0por \u00a0lo \u00a0tanto, \u00a0es \u00a0claro que carece de total inter\u00e9s y, de \u00a0otra, \u00a0 porque \u00a0 la \u00a0 propuesta, \u00a0 ya \u00a0respecto \u00a0de \u00a0su \u00a0defendido \u00a0JHONY \u00a0PARDO \u00a0DUARTE es, como se explic\u00f3, \u00a0intrascendente. \u00a0\u00a0<\/p>\n<p>En las anteriores condiciones, la censura se \u00a0inadmitir\u00e1. \u00a0\u00a0<\/p>\n<p>2. Cargos segundo y tercero. Causal tercera, \u00a0violaci\u00f3n \u00a0 \u00a0indirecta \u00a0 de \u00a0 la \u00a0 ley \u00a0 sustancial: \u00a0\u00a0<\/p>\n<p>En \u00a0 el \u00a0 segundo \u00a0 reparo \u00a0 el \u00a0 \u00a0censor \u00a0 \u00a0se\u00f1ala \u00a0 \u00a0que \u00a0el Tribunal incurri\u00f3 en error de hecho por falso raciocinio en \u00a0la \u00a0 valoraci\u00f3n \u00a0 del \u00a0 testimonio \u00a0de \u00a0Ra\u00fal \u00a0Pe\u00f1a \u00a0Mosquera, \u00a0 \u00a0 pues \u00a0 \u00a0 lo \u00a0 \u00a0 hizo \u00a0 \u00a0 \u201ccon \u00a0sesgo\u2026 \u00a0y \u00a0no \u00a0confront\u00f3 \u00a0este testimonio con las dem\u00e1s \u00a0declaraciones \u00a0que \u00a0hab\u00eda \u00a0rendido \u00a0en \u00a0oportunidad \u00a0anterior, \u00a0se \u00a0empe\u00f1\u00f3 en \u00a0vulnerar \u00a0las \u00a0reglas \u00a0de \u00a0la \u00a0sana \u00a0cr\u00edtica \u00a0como la l\u00f3gica, las reglas de la \u00a0experiencia \u00a0y \u00a0el \u00a0sentido com\u00fan las cuales de aplicarse correctamente hubiese \u00a0llegado \u00a0 \u00a0(sic) \u00a0 a \u00a0 la \u00a0conclusi\u00f3n \u00a0que \u00a0el \u00a0testimonio \u00a0del se\u00f1or Ra\u00fal Pe\u00f1a Mosquera, se encontraba \u00a0viciado \u00a0de \u00a0sospecha \u00a0y \u00a0a \u00a0dem\u00e1s \u00a0(sic) la \u00a0defensa \u00a0dentro \u00a0del escenario del juicio oral hab\u00eda impugnado \u00a0su credibilidad&#8221;. \u00a0\u00a0<\/p>\n<p>Despu\u00e9s se\u00f1ala que los juzgadores otorgaron \u00a0credibilidad \u00a0a \u00a0este \u00a0deponente, \u00a0sin \u00a0considerar \u00a0su \u00a0condici\u00f3n \u00a0de indigente \u00a0durante \u00a018 \u00a0a\u00f1os, \u201clo cual constituye un error que \u00a0debe \u00a0 ser \u00a0 estudiado \u00a0en \u00a0casaci\u00f3n, \u00a0debido \u00a0a \u00a0que, \u00a0desde \u00a0ese \u00a0momento \u00a0la \u00a0imparcialidad \u00a0que \u00a0se \u00a0debe predicar del juez de segunda instancia se encuentra \u00a0en \u00a0 suspenso \u00a0 y \u00a0 dir\u00eda \u00a0yo \u00a0un \u00a0poquito \u00a0m\u00e1s \u00a0en \u00a0entredicho\u201d. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, \u00a0 se \u00a0 le \u00a0otorg\u00f3 \u00a0confiabilidad \u00a0ignor\u00e1ndose \u00a0 que \u00a0 hab\u00eda \u00a0 rendido \u00a0 varias \u00a0entrevistas \u00a0previas \u00a0al \u00a0juicio \u00a0oral, \u00a0\u201cdonde \u00a0hab\u00eda manifestado circunstancias de \u00a0tiempo, \u00a0modo \u00a0y \u00a0lugar \u00a0diferentes \u00a0y \u00a0hab\u00eda incurrido en graves incoherencias \u00a0sustanciales \u00a0en el testimonio, al punto que fue impugnada su credibilidad en el \u00a0juicio oral\u201d. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0anterior, \u00a0contin\u00faa, \u00a0su \u00a0dicho ha \u00a0debido \u00a0ser \u00a0objeto \u00a0de cotejo frente \u201ca cada una de \u00a0las \u00a0declaraciones \u00a0rendidas\u201d, a cambio de lo cual se \u00a0le \u00a0concedi\u00f3 \u00a0credibilidad sin motivaci\u00f3n alguna, dejando de lado, reitera, su \u00a0personalidad, \u00a0pues por su condici\u00f3n de indigente durante el t\u00e9rmino se\u00f1alado \u00a0\u201ctiene \u00a0 \u00a0 una \u00a0 \u00a0 estructura \u00a0 \u00a0 de \u00a0 \u00a0 valores \u00a0negativa\u201d, \u00a0donde \u00a0son \u00a0ausentes \u00a0la lealtad, honra, \u00a0justicia y verdad, siendo, adem\u00e1s, proclive a cometer delitos. \u00a0\u00a0<\/p>\n<p>Igualmente, se hizo abstracci\u00f3n al hecho de \u00a0que \u00a0 \u00a0 \u00a0incurri\u00f3 \u00a0 \u00a0 \u00a0en \u00a0 \u00a0 \u00a0m\u00faltiples \u00a0 \u00a0 \u00a0contradicciones \u00a0 \u00a0 \u201crespecto \u00a0de \u00a0las \u00a0declaraciones \u00a0precedentes del juicio oral\u201d \u00a0y \u00a0el \u00a0protocolo \u00a0de necropsia de la menor v\u00edctima de \u00a0los hechos. \u00a0\u00a0<\/p>\n<p>Adicionalmente \u00a0no \u00a0se \u00a0tuvo \u00a0en \u00a0cuenta que \u00a0ten\u00eda \u00a0inter\u00e9s \u00a0en \u00a0el \u00a0proceso, \u00a0representado \u00a0por \u00a0el \u00a0hecho \u00a0de \u00a0que con la \u00a0delaci\u00f3n \u00a0en \u00a0contra \u00a0de \u00a0PARDO \u00a0DUARTE pretend\u00eda \u00a0 obtener \u00a0una \u00a0rebaja \u00a0de \u00a0pena \u00a0ofrecida \u00a0por \u00a0el \u00a0ente \u00a0acusador, \u00a0no \u00a0obstante \u00a0estar expresamente prohibidas en el art\u00edculo 199 de la \u00a0Ley \u00a01098 \u00a0de \u00a02006, lo cual \u201ctilda de sospechoso la \u00a0credibilidad\u201d. \u00a0\u00a0<\/p>\n<p>Y, \u00a0de \u00a0id\u00e9ntica \u00a0manera, \u00a0porque \u00a0no \u00a0fue \u00a0valorada \u00a0junto \u00a0con las dem\u00e1s pruebas obrantes en el plenario, como el informe \u00a0de \u00a0necropsia \u00a0que \u00a0da \u00a0cuenta de heridas no referidas por el testigo, siendo su \u00a0\u00fanica \u00a0motivaci\u00f3n \u00a0para \u00a0delatar \u00a0a su prohijado evitar la sindicaci\u00f3n por el \u00a0delito \u00a0de acceso carnal violento, raz\u00f3n por la cual opt\u00f3 por aceptar tan solo \u00a0la comisi\u00f3n del homicidio. \u00a0\u00a0<\/p>\n<p>Sobre \u00a0el \u00a0particular, \u00a0aduce, \u00a0conforme \u00a0al \u00a0informe \u00a0de \u00a0necropsia \u00a0resultaba \u00a0evidente la ocurrencia del delito sexual, sin \u00a0embargo, \u00a0\u201cfue \u00a0tan descuidada y torpe la fiscal\u00eda \u00a0que \u00a0en \u00a0documentos \u00a0que \u00a0no aparecen incorporados al expediente pero que fueron \u00a0descubiertos \u00a0 por \u00a0la \u00a0fiscal\u00eda \u00a0(sic) \u00a0a \u00a0la \u00a0defensa, \u00a0que \u00a0demuestran \u00a0la \u00a0imprudencia \u00a0del fiscal y sus \u00a0colaboradores, \u00a0por \u00a0no \u00a0investigar los hechos tal y como sucedieron y en unidad \u00a0de \u00a0 circunstancia \u00a0 y \u00a0 hecho \u00a0 o \u00a0 sea \u00a0acceso \u00a0carnal \u00a0violento \u00a0y \u00a0homicidio \u00a0agravado\u201d. \u00a0\u00a0<\/p>\n<p>De \u00a0 esta \u00a0manera, \u00a0se\u00f1ala, \u00a0\u201cel \u00a0falso \u00a0raciocinio \u00a0en que incurri\u00f3 tanto el juez de primera \u00a0instancia \u00a0 como \u00a0 el \u00a0 de \u00a0 segunda, \u00a0 primero \u00a0(sic) \u00a0fue \u00a0darle \u00a0certeza \u00a0a un criminal de la peor cala\u00f1a \u00a0como \u00a0es el se\u00f1or Ra\u00fal Pe\u00f1a Mosquera y segundo omitir que esta investigaci\u00f3n \u00a0dar\u00eda \u00a0otras \u00a0resultas \u00a0y \u00a0otras \u00a0conclusiones, \u00a0si \u00a0se \u00a0hubiera investigado en \u00a0concurso \u00a0 el \u00a0 acceso \u00a0 carnal \u00a0con \u00a0el \u00a0homicidio, \u00a0puesto \u00a0que \u00a0dar\u00eda \u00a0plena \u00a0credibilidad \u00a0y \u00a0vigencia \u00a0al hecho estipulado probatoriamente que el m\u00f3vil del \u00a0crimen \u00a0o \u00a0la \u00a0raz\u00f3n \u00a0que \u00a0motivo \u00a0(sic) al \u00a0se\u00f1or \u00a0Ra\u00fal \u00a0Pe\u00f1a \u00a0Mosquera \u00a0a \u00a0consumar \u00a0el homicidio de la \u00a0menor, \u00a0no \u00a0era otro que el de ocultar o encubrir el delito contra la libertad e \u00a0integridad \u00a0 \u00a0 \u00a0sexual \u00a0 \u00a0 \u00a0en \u00a0 \u00a0 contra \u00a0 \u00a0 de \u00a0 \u00a0 la \u00a0 \u00a0 menor\u201d.\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>El \u00a0siguiente aspecto que configura el yerro \u00a0invocado \u00a0consisti\u00f3, \u00a0dice, \u00a0en \u00a0haberle \u00a0otorgado \u00a0credibilidad a Pe\u00f1a \u00a0 Mosquera \u00a0 no \u00a0obstante \u00a0que \u00a0la \u00a0delaci\u00f3n \u00a0contra \u00a0su \u00a0patrocinado \u00a0se \u00a0obtuvo \u00a0mediante \u00a0la \u00a0promesa \u00a0falsa \u00a0de \u00a0otorgarle \u00a0beneficios \u00a0punitivos cuando ellos est\u00e1n excluidos para este tipo de \u00a0delitos, \u00a0de \u00a0conformidad \u00a0con \u00a0la \u00a0Ley \u00a01098 de 2006, frente a lo cual la Corte \u00a0\u201cno \u00a0 puede \u00a0 permitir \u00a0 o \u00a0conestar \u00a0(sic) \u00a0este \u00a0tipo \u00a0de \u00a0conductas \u00a0de \u00a0los \u00a0funcionarios \u00a0 judiciales, \u00a0que \u00a0manipulan \u00a0y \u00a0contaminan \u00a0a \u00a0los \u00a0testigos \u00a0que \u00a0concurren \u00a0a \u00a0los \u00a0juicios \u00a0como autores materiales\u201d, \u00a0por constituir delito de fraude procesal. \u00a0\u00a0<\/p>\n<p>Otro \u00a0 error \u00a0radic\u00f3, \u00a0agrega, \u00a0en \u00a0haber \u00a0descartado \u00a0\u201cde \u00a0un solo tajo todos los testimonios \u00a0aportados \u00a0 por \u00a0 la \u00a0defensa, \u00a0que \u00a0demostraba \u00a0(sic) \u00a0que el m\u00f3vil del homicidio no fue otro que la manera \u00a0como \u00a0el \u00a0se\u00f1or \u00a0Ra\u00fal \u00a0Pe\u00f1a \u00a0Mosquera \u00a0trato \u00a0(sic) \u00a0de \u00a0 \u00a0encubrir \u00a0 el \u00a0 delito \u00a0 de \u00a0 acceso \u00a0 carnal \u00a0violento\u201d. Al contrario, le concedi\u00f3 cr\u00e9dito a las \u00a0referencias \u00a0acerca \u00a0de \u00a0la \u00a0condici\u00f3n \u00a0de \u00a0\u201chombre \u00a0problem\u00e1tico\u201d \u00a0de \u00a0su prohijado, sin estar siquiera \u00a0establecida \u00a0la \u00a0existencia \u00a0del \u00a0arma \u00a0de \u00a0fuego \u00a0con \u00a0la \u00a0que intimidaba a las \u00a0personas de la regi\u00f3n. \u00a0\u00a0<\/p>\n<p>Sumado a ello, no fueron aportados al juicio \u00a0oral \u00a0 los \u00a0escritos \u00a0recibidos \u00a0tanto \u00a0por \u00a0el \u00a0autor \u00a0material \u00a0como \u00a0por \u00a0los \u00a0progenitores \u00a0de la v\u00edctima contentivos de amenazas por parte del procesado, ni \u00a0constatada su supuesta fuga de la zona. \u00a0\u00a0<\/p>\n<p>En \u00a0virtud \u00a0de \u00a0los errores referidos, todos \u00a0ellos, \u00a0a su juicio, con car\u00e1cter trascendente, \u201clo \u00a0m\u00ednimo \u00a0que debi\u00f3 fue absolverse a mi cliente, por la aplicaci\u00f3n del apotegma \u00a0del \u00a0in \u00a0dubio \u00a0pro \u00a0reo\u201d, \u00a0t\u00e9rminos \u00a0en los cuales \u00a0solicita casar el fallo impugnado. \u00a0\u00a0<\/p>\n<p>En \u00a0 \u00a0la \u00a0 tercera \u00a0 censura, \u00a0por \u00a0su \u00a0parte, plantea un error de hecho a consecuencia de falso \u00a0juicio \u00a0de \u00a0existencia \u00a0por \u00a0omisi\u00f3n \u201cal dejarse de \u00a0valorar \u00a0la \u00a0estipulaci\u00f3n \u00a0probatoria, \u00a0respecto \u00a0de \u00a0la violaci\u00f3n de la menor \u00a0J.A.V. (sic), que sustentaba \u00a0el \u00a0m\u00f3vil \u00a0de \u00a0la muerte de la menor, para encubrir el acceso carnal violento a \u00a0la \u00a0 \u00a0 \u00a0 menor \u00a0 \u00a0 \u00a0 J.A.V. \u00a0 \u00a0 \u00a0(sic)\u201d. \u00a0\u00a0<\/p>\n<p>Con \u00a0lo \u00a0anterior, \u00a0se\u00f1ala, se violaron los \u00a0principios \u00a0consagrados \u00a0en el art\u00edculo 356 de la Ley 906 de 2004, acerca de la \u00a0estipulaci\u00f3n \u00a0 \u00a0probatoria \u00a0 \u00a0entre \u00a0 \u00a0Fiscal\u00eda \u00a0 \u00a0y \u00a0 \u00a0defensa \u00a0 \u201ccon \u00a0el \u00a0\u00fanico \u00a0objeto \u00a0de \u00a0no \u00a0sujetar \u00a0el debate al hecho del \u00a0acceso carnal violento\u201d. \u00a0\u00a0<\/p>\n<p>Recuerda \u00a0c\u00f3mo entre las partes en menci\u00f3n \u00a0\u201cse \u00a0 estipulo \u00a0 (sic) \u00a0como \u00a0cierto el hecho que la menor J.A.V. \u00a0(sic), \u00a0fue objeto del delito de acceso \u00a0carnal \u00a0 violento \u00a0 por \u00a0 parte \u00a0 de \u00a0 un \u00a0persona \u00a0indeterminada\u201d. \u00a0\u00a0<\/p>\n<p>Pero la defensa, a\u00f1ade, logr\u00f3 demostrar la \u00a0ineptitud \u00a0de \u00a0la Fiscal\u00eda para investigar ese comportamiento, a pesar de estar \u00a0plenamente \u00a0probada su realizaci\u00f3n en la humanidad de la v\u00edctima, como as\u00ed lo \u00a0deprec\u00f3 \u00a0la \u00a0defensa \u00a0en \u00a0su \u00a0teor\u00eda \u00a0del caso al aducir que el autor material \u00a0pretendi\u00f3 \u00a0encubrirla, \u00a0conducta \u00a0que \u00a0\u201cactualmente \u00a0cursa en investigaci\u00f3n\u201d. \u00a0\u00a0<\/p>\n<p>Considera as\u00ed que los juzgadores incurrieron \u00a0en \u00a0el error denunciado \u201cal no valorar que el m\u00f3vil \u00a0del \u00a0homicidio \u00a0de \u00a0la \u00a0menor \u00a0fue \u00a0el encubrimiento de la violaci\u00f3n plenamente \u00a0probado \u00a0 dentro \u00a0 del \u00a0 proceso \u00a0 penal, \u00a0 a \u00a0 trav\u00e9s \u00a0 de \u00a0 la \u00a0estipulaci\u00f3n \u00a0probatoria\u201d. En consecuencia, ha debido absolverse a \u00a0PARDO \u00a0DUARTE \u00a0por falta de \u00a0certeza \u00a0 \u201cpuesto \u00a0 que \u00a0existieron \u00a0dos \u00a0m\u00f3viles \u00a0probados \u00a0uno las venganza y la ri\u00f1a (sic) \u00a0entre \u00a0la \u00a0familia de PARDO DUARTE y Ariza Vargas. Otro el m\u00f3vil \u00a0que \u00a0 \u00a0 el \u00a0 \u00a0 se\u00f1or \u00a0 \u00a0 Ra\u00fal \u00a0 \u00a0Pe\u00f1a \u00a0 \u00a0Mosquera, \u00a0 \u00a0asesino \u00a0 \u00a0(sic) \u00a0a la ni\u00f1a para encubrir el acceso \u00a0carnal \u00a0violento, por esto deb\u00eda darle aplicaci\u00f3n al principio de in dubio pro \u00a0reo, \u00a0 estrictamente \u00a0 ligado \u00a0al \u00a0de \u00a0presunci\u00f3n \u00a0de \u00a0inocencia\u201d. \u00a0\u00a0<\/p>\n<p>Por lo expuesto, depreca casar el fallo para \u00a0que, \u00a0en \u00a0su \u00a0lugar, se dicte uno de reemplazo mediante el cual se absuelva a su \u00a0defendido, \u00a0\u201cy \u00a0en \u00a0consecuencia \u00a0se \u00a0le otorgue al \u00a0procesado \u00a0la \u00a0libertad \u00a0inmediata \u00a0e incondicional\u201d. \u00a0\u00a0<\/p>\n<p>Consideraciones de la Sala: \u00a0<\/p>\n<p>Como \u00a0quiera \u00a0que \u00a0el \u00a0censor \u00a0formula \u00a0en \u00a0las \u00a0censuras \u00a0objeto \u00a0de \u00a0estudio \u00a0 la \u00a0 causal \u00a0de \u00a0violaci\u00f3n \u00a0 indirecta \u00a0 de \u00a0 la \u00a0ley \u00a0sustancial \u00a0a \u00a0consecuencia \u00a0de \u00a0errores de \u00a0hecho \u00a0 \u00a0por \u00a0 \u00a0falso \u00a0 \u00a0raciocinio \u00a0 \u00a0(segundo \u00a0 \u00a0 \u00a0 cargo \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0la \u00a0demanda) \u00a0y \u00a0falso \u00a0 juicio \u00a0 de \u00a0existencia \u00a0(tercer \u00a0cargo), \u00a0 \u00a0oportuno \u00a0 \u00a0se \u00a0 \u00a0ofrece \u00a0 \u00a0evocar \u00a0 sus \u00a0caracter\u00edsticas \u00a0 \u00a0 \u00a0principales \u00a0 \u00a0 de \u00a0acuerdo \u00a0con \u00a0el \u00a0criterio \u00a0pac\u00edfico \u00a0e inveterado de la Sala. \u00a0\u00a0<\/p>\n<p>As\u00ed, \u00a0en \u00a0cuanto al falso raciocinio se ha \u00a0dicho \u00a0que \u00a0tiene \u00a0ocurrencia \u00a0cuando \u00a0el juzgador se aparta de las reglas de la \u00a0sana \u00a0cr\u00edtica \u00a0en \u00a0el \u00a0proceso \u00a0valorativo \u00a0de \u00a0las \u00a0pruebas.\u00a0 Para que la \u00a0propuesta \u00a0basada \u00a0en \u00a0esa \u00a0modalidad \u00a0de \u00a0error \u00a0goce de imprescindible aptitud \u00a0argumentativa \u00a0y\u00a0 \u00a0l\u00f3gica, \u00a0el \u00a0demandante \u00a0est\u00e1 \u00a0compelido, como primera \u00a0medida, \u00a0a \u00a0identificar \u00a0la \u00a0prueba \u00a0sobre la cual recae; luego, a establecer el \u00a0m\u00e9rito \u00a0que se le otorg\u00f3 en la sentencia y a se\u00f1alar cu\u00e1l es el postulado de \u00a0la \u00a0sana \u00a0cr\u00edtica \u00a0en su criterio vulnerado, es decir, el principio l\u00f3gico, la \u00a0m\u00e1xima de la experiencia o la regla cient\u00edfica quebrantada. \u00a0\u00a0<\/p>\n<p>Acto \u00a0seguido \u00a0debe proceder a vincular esa \u00a0apreciaci\u00f3n \u00a0con \u00a0la \u00a0regla \u00a0aludida demostrando en d\u00f3nde radica el desv\u00edo y, \u00a0por \u00a0\u00faltimo, \u00a0est\u00e1 \u00a0obligado a precisar la trascendencia del error frente a la \u00a0ley \u00a0sustancial, \u00a0lo \u00a0cual \u00a0exige exponer los argumentos conducentes a demostrar \u00a0que \u00a0la sentencia impugnada se debe modificar en favor del inter\u00e9s representado \u00a0como \u00a0consecuencia \u00a0necesaria \u00a0del \u00a0error, \u00a0tarea que, ineludiblemente, entra\u00f1a \u00a0abordar \u00a0 la \u00a0 totalidad \u00a0 de \u00a0los \u00a0medios \u00a0de \u00a0persuasi\u00f3n \u00a0en \u00a0los \u00a0cuales \u00a0se \u00a0sustenta.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Por su parte, respecto del denominado error \u00a0de \u00a0hecho por falso juicio de existencia se ha dicho que tiene ocurrencia cuando \u00a0una \u00a0probanza es excluida de la valoraci\u00f3n que efect\u00faa el juzgador no obstante \u00a0haber \u00a0sido allegada al proceso en forma legal, regular y oportuna (ignorancia u \u00a0omisi\u00f3n) \u00a0y, en segundo lugar, cuando el juzgador lo crea a pesar de no existir \u00a0materialmente en el proceso (suposici\u00f3n o ideaci\u00f3n). \u00a0\u00a0<\/p>\n<p>Frente \u00a0a \u00a0estas \u00a0hip\u00f3tesis, el recurrente \u00a0est\u00e1 \u00a0obligado \u00a0a \u00a0(i) \u00a0identificar \u00a0el \u00a0medio \u00a0de prueba que en su criterio se \u00a0omiti\u00f3 \u00a0 o \u00a0se \u00a0supuso, \u00a0(ii) \u00a0establecer \u00a0la \u00a0incidencia \u00a0de \u00a0esa \u00a0omisi\u00f3n \u00a0o \u00a0suposici\u00f3n \u00a0probatoria \u00a0en \u00a0la \u00a0decisi\u00f3n \u00a0que \u00a0se \u00a0controvierte y en favor del \u00a0inter\u00e9s \u00a0que \u00a0se \u00a0representa, lo cual comporta la necesidad de demostrar que el \u00a0fallo \u00a0atacado no se mantiene con otros elementos de juicio y (iii) demostrar de \u00a0qu\u00e9 \u00a0forma \u00a0se viol\u00f3 la ley sustancial con ese defecto de apreciaci\u00f3n, ya sea \u00a0por falta de aplicaci\u00f3n o por aplicaci\u00f3n indebida. \u00a0\u00a0<\/p>\n<p>Pues \u00a0 \u00a0 \u00a0bien, \u00a0 \u00a0 \u00a0confrontados \u00a0los \u00a0anteriores derroteros con los planteamientos del \u00a0actor \u00a0contenidos \u00a0en \u00a0las \u00a0dos \u00a0censuras \u00a0objeto \u00a0de \u00a0an\u00e1lisis \u00a0 se \u00a0desprende \u00a0el \u00a0incumplimiento de\u00a0 \u00a0la \u00a0carga \u00a0argumentativa \u00a0y \u00a0demostrativa \u00a0que \u00a0le \u00a0compet\u00eda \u00a0para tenerlos por \u00a0adecuadamente sustentados.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Lo \u00a0dicho, en tanto se observa que en toda \u00a0su \u00a0extensi\u00f3n \u00a0lo \u00a0que \u00a0pretende, \u00a0frente \u00a0a los dos \u00a0cargos, \u00a0es que su \u00a0 \u00a0 \u00a0 criterio \u00a0 \u00a0 \u00a0personal \u00a0de \u00a0valoraci\u00f3n \u00a0de las pruebas \u00a0prevalezca \u00a0 \u00a0 \u00a0 sobre \u00a0 \u00a0 \u00a0el \u00a0 \u00a0 \u00a0expuesto \u00a0por \u00a0los \u00a0juzgadores, \u00a0fin que, \u00a0como \u00a0mucho lo ha precisado la Sala, ri\u00f1e \u00a0con \u00a0la \u00a0naturaleza extraordinaria del \u00a0recurso, \u00a0incompatible \u00a0con \u00a0una \u00a0tercera \u00a0instancia, \u00a0y \u00a0 resulta \u00a0desconocedor \u00a0 \u00a0 de \u00a0 \u00a0 la \u00a0 doble \u00a0presunci\u00f3n \u00a0de \u00a0acierto \u00a0y \u00a0legalidad \u00a0que \u00a0ampara \u00a0al \u00a0fallo impugnado. \u00a0\u00a0<\/p>\n<p>Ello \u00a0 se \u00a0advierte \u00a0 palmario \u00a0 en \u00a0relaci\u00f3n \u00a0con \u00a0el \u00a0segundo \u00a0cargo \u00a0donde a cambio de \u00a0individualizar \u00a0reglas de la l\u00f3gica, la ciencia o la experiencia vulneradas con \u00a0la \u00a0apreciaci\u00f3n \u00a0probatoria, simple y llanamente, y de forma por dem\u00e1s extensa \u00a0y \u00a0 repetitiva, \u00a0 se \u00a0escuda \u00a0en \u00a0su \u00a0transgresi\u00f3n \u00a0para \u00a0exponer \u00a0su \u00a0personal \u00a0apreciaci\u00f3n \u00a0sobre las pruebas, principalmente frente \u00a0al \u00a0 testimonio \u00a0de \u00a0Ra\u00fal \u00a0Pe\u00f1a \u00a0 Mosquera \u00a0 quien \u00a0fuera condenado como autor \u00a0material \u00a0 \u00a0 \u00a0 \u00a0 de \u00a0 \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0 \u00a0conducta3. \u00a0\u00a0<\/p>\n<p>Para tal objetivo \u00a0se \u00a0vale, \u00a0incluso, \u00a0de \u00a0cuestionamientos que apuntan \u00a0hacia \u00a0 su \u00a0 condici\u00f3n \u00a0 personal, \u00a0como \u00a0el \u00a0hecho \u00a0de \u00a0haber \u00a0sido \u00a0indigente \u00a0durante \u00a0 18 \u00a0 a\u00f1os, \u00a0 lo \u00a0 cual \u00a0 lo \u00a0lleva \u00a0 \u00a0 a \u00a0 \u00a0 calificarlo \u00a0 \u00a0de \u00a0 \u00a0persona \u00a0 \u00a0con \u00a0 \u00a0\u201cuna \u00a0 \u00a0 estructura \u00a0 \u00a0 de \u00a0 \u00a0 valores \u00a0 \u00a0negativa\u201d, \u00a0 \u00a0en \u00a0 donde \u00a0 carece \u00a0 de \u00a0lealtad, \u00a0honra, \u00a0justicia \u00a0y \u00a0verdad, \u00a0adem\u00e1s \u00a0de \u00a0proclive a \u00a0cometer \u00a0 \u00a0 \u00a0delitos \u00a0 \u00a0 y \u00a0 \u00a0 de \u00a0 \u00a0 \u201cdelincuente \u00a0de \u00a0la \u00a0peor \u00a0cala\u00f1a\u201d, \u00a0reproche \u00a0 que \u00a0 va \u00a0 en \u00a0contrav\u00eda \u00a0con \u00a0un m\u00e9todo \u00a0de \u00a0valoraci\u00f3n \u00a0racional \u00a0de \u00a0la \u00a0prueba \u00a0y \u00a0con \u00a0la \u00a0misma \u00a0jurisprudencia \u00a0de \u00a0esta Sala, seg\u00fan la cual \u00a0estos \u00a0 aspectos \u00a0 no \u00a0inciden \u00a0necesariamente \u00a0en \u00a0la \u00a0veracidad \u00a0de un \u00a0testimonio, \u00a0como as\u00ed se se\u00f1al\u00f3 en la siguiente determinaci\u00f3n, cuyos apartes \u00a0pertinentes \u00a0 oportuno \u00a0 se \u00a0 ofrece \u00a0transcribir:\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u201cSi \u00a0bien \u00a0la valoraci\u00f3n del testimonio \u00a0involucra \u00a0 aspectos \u00a0 como \u00a0 la \u00a0 personalidad \u00a0 del \u00a0declarante, \u00a0no \u00a0menos \u00a0cierto \u00a0es que el conjunto de valores morales o \u00e9ticos \u00a0que \u00a0la \u00a0integran \u00a0no \u00a0constituyen \u00a0condici\u00f3n \u00a0que por s\u00ed misma descalifique o \u00a0acredite \u00a0 un \u00a0testimonio, \u00a0de \u00a0modo \u00a0que \u00a0corresponde \u00a0al \u00a0juzgador \u00a0deducir \u00a0o \u00a0aprehender \u00a0la \u00a0verdad \u00a0bajo los par\u00e1metros de la libre persuasi\u00f3n, desechando \u00a0lo \u00a0que \u00a0contrar\u00eda \u00a0la \u00a0realidad \u00a0probatoria \u00a0y \u00a0el \u00a0sentido com\u00fan\u201d4 \u00a0 \u00a0 \u00a0 \u00a0 (subraya fuera de texto). \u00a0\u00a0<\/p>\n<p>La \u00a0cr\u00edtica \u00a0restante enfilada contra este \u00a0testimonio, \u00a0esto \u00a0es, \u00a0(i) \u00a0que \u00a0incurri\u00f3 \u00a0en \u00a0algunas contradicciones con sus \u00a0entrevistas \u00a0iniciales, \u00a0las \u00a0cuales \u00a0no \u00a0concreta en la censura y que, como \u00e9l \u00a0mismo \u00a0 lo \u00a0 sostiene, \u00a0fueron \u00a0utilizadas \u00a0por \u00a0la \u00a0defensa \u00a0para \u00a0impugnar \u00a0su \u00a0credibilidad, \u00a0a \u00a0pesar \u00a0de \u00a0lo cual los juzgadores no lo consideraron relevante \u00a0para \u00a0minarle \u00a0poder \u00a0suasorio; (ii) que su dicho no coincide con lo plasmado en \u00a0el \u00a0protocolo \u00a0de necropsia, aspecto que no se comparte en los fallos; (iii) que \u00a0ten\u00eda \u00a0inter\u00e9s \u00a0en \u00a0el \u00a0proceso, \u00a0representado \u00a0por \u00a0el \u00a0hecho \u00a0de \u00a0que con la \u00a0delaci\u00f3n \u00a0pretend\u00eda \u00a0obtener una rebaja de pena ofrecida por el ente acusador, \u00a0no \u00a0obstante estar expresamente prohibidas en el art\u00edculo 199 de la Ley 1098 de \u00a02006 \u00a0y \u00a0(iv) que tuvo por objeto evitar la sindicaci\u00f3n por el delito de acceso \u00a0carnal \u00a0violento \u00a0cometido \u00a0sobre \u00a0la \u00a0menor \u00a0v\u00edctima \u00a0de \u00a0los \u00a0hechos, ninguna \u00a0relaci\u00f3n \u00a0guardan, en la forma como son presentados, con el pretextado yerro de \u00a0valoraci\u00f3n \u00a0probatoria, \u00a0ni \u00a0con ninguno otro viable en sede de casaci\u00f3n, pues \u00a0de \u00a0ellas \u00a0s\u00f3lo \u00a0aflora, \u00a0se insiste, el prop\u00f3sito de sacar avante su criterio \u00a0personal valorativo. \u00a0\u00a0<\/p>\n<p>De otro lado, el argumento conforme al cual \u00a0no \u00a0se \u00a0ahond\u00f3 \u00a0en \u00a0la \u00a0investigaci\u00f3n \u00a0por el delito de acceso carnal violento \u00a0cometido \u00a0contra \u00a0la \u00a0v\u00edctima, \u00a0am\u00e9n \u00a0de \u00a0rebasar \u00a0el \u00a0\u00e1mbito \u00a0de \u00a0la \u00a0causal \u00a0seleccionada, \u00a0no \u00a0tiene \u00a0ninguna \u00a0trascendencia \u00a0frente \u00a0a \u00a0la \u00a0responsabilidad \u00a0declarada \u00a0 \u00a0de\u00a0 \u00a0 \u00a0PARDO \u00a0 DUARTE \u00a0porque \u00a0la \u00a0delaci\u00f3n \u00a0efectuada \u00a0en \u00a0su \u00a0contra \u00a0por Pe\u00f1a \u00a0 Mosquera \u00a0 est\u00e1 \u00a0 avalada \u00a0 por \u00a0consistentes \u00a0indicios construidos por los juzgadores (amenazas previas, m\u00f3vil, \u00a0personalidad \u00a0del \u00a0procesado \u00a0y fuga), cuyo cuestionamiento en el cargo, adem\u00e1s \u00a0de \u00a0no \u00a0responder a la forma adecuada de atacar el indicio en sede de casaci\u00f3n, \u00a0se \u00a0restringe \u00a0a \u00a0exponer \u00a0su \u00a0particular criterio de valoraci\u00f3n, por fuera del \u00a0marco \u00a0de \u00a0las \u00a0reglas \u00a0de \u00a0la \u00a0sana \u00a0cr\u00edtica, \u00a0a las que solo refiere de forma \u00a0enunciativa. \u00a0\u00a0<\/p>\n<p>Antes \u00a0de \u00a0culminar \u00a0lo concerniente a este \u00a0reparo, \u00a0conviene \u00a0dejar \u00a0en claro que el planteamiento del censor en el sentido \u00a0de \u00a0que \u00a0la \u00a0delaci\u00f3n \u00a0del testigo en contra de su prohijado se obtuvo mediante \u00a0maniobras \u00a0enga\u00f1osas \u00a0y \u00a0delictivas \u00a0del \u00a0ente \u00a0acusador \u00a0quienes le ofrecieron \u00a0beneficios \u00a0punitivos \u00a0a \u00a0pesar de estar expresamente prohibidos en el art\u00edculo \u00a0199 \u00a0de la Ley 1098 de 2006, no deja de ser sof\u00edstico en la medida en que dicha \u00a0disposici\u00f3n, \u00a0 \u00a0 \u00a0en \u00a0 \u00a0 \u00a0su \u00a0 \u00a0 \u00a0numeral \u00a0 \u00a0 \u00a08, \u00a0 \u00a0 \u00a0permite \u00a0 \u00a0 \u201clos \u00a0beneficios \u00a0por \u00a0colaboraci\u00f3n \u00a0consagrados \u00a0en el C\u00f3digo de Procedimiento Penal\u201d, \u00a0como as\u00ed tambi\u00e9n lo ha reiterado esta Sala: \u00a0\u00a0<\/p>\n<p>\u201cEs \u00a0decir, \u00a0con \u00a0el \u00a0numeral \u00a08\u00ba \u00a0del \u00a0art\u00edculo \u00a0199 del C\u00f3digo de la Infancia y la Adolescencia, el legislador dej\u00f3 \u00a0en \u00a0claro \u00a0su \u00a0manifiesta \u00a0voluntad \u00a0de \u00a0que \u00a0a \u00a0las personas procesadas por los \u00a0delitos \u00a0se\u00f1alados \u00a0en \u00a0el \u00a0inciso \u00a01\u00ba \u00a0ib\u00eddem, \u00a0que \u00a0tengan como v\u00edctimas a \u00a0menores \u00a0de \u00a0edad, \u00a0de \u00a0ninguna \u00a0manera \u00a0se les otorgar\u00e1 beneficio, subrogado o \u00a0prebenda \u00a0de \u00a0cualquier tipo, a menos que se trate de \u00a0un \u00a0 \u00a0asunto \u00a0 \u00a0de \u00a0 \u00a0colaboraci\u00f3n \u00a0 \u00a0eficaz \u00a0 \u00a0con \u00a0 la \u00a0 administraci\u00f3n \u00a0 de \u00a0justicia\u201d5 \u00a0 \u00a0 (subraya \u00a0 \u00a0fuera \u00a0 \u00a0de \u00a0texto). \u00a0\u00a0<\/p>\n<p>De otro lado, d\u00edgase que la misma cr\u00edtica \u00a0en \u00a0cuanto \u00a0a \u00a0que lo \u00fanico pretendido es sacar avante su criterio subjetivo de \u00a0valoraci\u00f3n \u00a0de \u00a0los \u00a0medios \u00a0de \u00a0prueba \u00a0surge \u00a0en \u00a0relaci\u00f3n \u00a0con \u00a0el reproche \u00a0consistente \u00a0en \u00a0haberse desechado elementos de juicio favorables al implicado y \u00a0por \u00a0raz\u00f3n \u00a0de no haber sido aportados al juicio los escritos que demostrar\u00edan \u00a0las \u00a0amenazas \u00a0por parte del procesado contra el autor material de la conducta y \u00a0los \u00a0progenitores \u00a0de \u00a0la \u00a0v\u00edctima, \u00a0en \u00a0tanto constituyen elementos que, en el \u00a0primer \u00a0caso, \u00a0conced\u00edan \u00a0m\u00e9rito \u00a0al \u00a0dicho de su defendido, y, en el segundo, \u00a0desvirtuaban \u00a0la \u00a0prueba \u00a0de cargo, pero su exposici\u00f3n, se insiste, se presenta \u00a0al \u00a0margen \u00a0de \u00a0los errores de apreciaci\u00f3n probatoria con incidencia para mutar \u00a0el sentido del fallo. \u00a0\u00a0<\/p>\n<p>Ahora \u00a0bien, \u00a0en \u00a0cuanto \u00a0a \u00a0la \u00a0propuesta \u00a0contenida \u00a0 \u00a0en \u00a0 \u00a0la \u00a0 tercera \u00a0 censura \u00a0se \u00a0advierte \u00a0c\u00f3mo, \u00a0de un lado, tambi\u00e9n resulta intrascendente, \u00a0por \u00a0limitarse \u00a0a \u00a0sustentar la hip\u00f3tesis de que el testigo y autor material de \u00a0la \u00a0conducta \u00a0Pe\u00f1a Mosquera \u00a0delat\u00f3 \u00a0a \u00a0PARDO DUARTE con \u00a0el \u00a0fin \u00a0de encubrir su responsabilidad en el acceso carnal violento a la menor, \u00a0haciendo \u00a0abstracci\u00f3n, \u00a0como \u00a0ya se dijo, de los m\u00faltiples elementos de juicio \u00a0de \u00a0tipo \u00a0indiciario considerados por los falladores para respaldar la veracidad \u00a0del relato incriminante. \u00a0\u00a0<\/p>\n<p>Y, \u00a0de \u00a0otro, en cuanto el planteamiento no \u00a0consulta \u00a0con \u00a0la realidad procesal y, por lo mismo, con el denominado principio \u00a0de \u00a0correcci\u00f3n \u00a0material, \u00a0regente \u00a0en \u00a0sede \u00a0de \u00a0casaci\u00f3n, al tergiversar los \u00a0t\u00e9rminos \u00a0de \u00a0la \u00a0estipulaci\u00f3n probatoria acordada entre el ente acusador y la \u00a0defensa. \u00a0\u00a0<\/p>\n<p>Ciertamente, \u00a0 las \u00a0 partes \u00a0en \u00a0menci\u00f3n \u00a0acordaron \u00a0el \u00a0hecho \u00a0de \u00a0que la menor tambi\u00e9n fue v\u00edctima de un acceso carnal \u00a0violento, \u00a0pero \u00a0nunca, \u00a0como \u00a0lo aduce el censor para demostrar su pretensi\u00f3n, \u00a0que \u00a0este delito fue el m\u00f3vil que tuvo Pe\u00f1a Mosquera \u00a0para ocasionarle la muerte, tanto as\u00ed que \u00e9ste neg\u00f3 \u00a0su \u00a0realizaci\u00f3n. \u00a0Adem\u00e1s, \u00a0una \u00a0estipulaci\u00f3n \u00a0en ese sentido desbordar\u00eda los \u00a0t\u00e9rminos de la figura, conforme lo ha precisado esta Sala: \u00a0\u00a0<\/p>\n<p>\u201cFrente \u00a0al punto antes destacado, vale \u00a0reiterar \u00a0que \u00a0el acuerdo o el pacto celebrado entre \u00a0la \u00a0 fiscal\u00eda \u00a0 y \u00a0 la \u00a0 defensa \u00a0 se \u00a0 centra \u00a0 sobre \u00a0 los \u00a0 hechos \u00a0 o \u00a0 sus \u00a0circunstancias,\u00a0 \u00a0y \u00a0no sobre la incorporaci\u00f3n \u00a0al \u00a0debate \u00a0oral \u00a0y \u00a0p\u00fablico \u00a0de \u00a0un determinado medio de convicci\u00f3n, elemento \u00a0material probatorio, evidencia f\u00edsica o informe. \u00a0\u00a0<\/p>\n<p>En \u00a0tales \u00a0condiciones, \u00a0una \u00a0vez que los \u00a0intervinientes \u00a0 del \u00a0 juicio \u00a0oral \u00a0y \u00a0p\u00fablico \u00a0han \u00a0manifestado \u00a0al \u00a0juez \u00a0de \u00a0conocimiento \u00a0 \u00a0que \u00a0 \u00a0celebraron \u00a0 \u00a0estipulaciones \u00a0 probatorias \u00a0 sobre \u00a0un \u00a0hecho \u00a0o \u00a0sus \u00a0circunstancias, \u00a0claro \u00a0resulta \u00a0que \u00a0la \u00a0actividad \u00a0probatoria no puede recaer sobre el mismo a fin de dar por demostrado \u00a0lo \u00a0que \u00a0ya se dio por establecido en virtud de dicho acuerdo o, para oponerse a \u00a0\u00e9l \u00a0 \u00a0 \u00a0durante \u00a0 \u00a0 el \u00a0 \u00a0 debate\u201d6 \u00a0(subraya \u00a0fuera \u00a0de texto). \u00a0\u00a0<\/p>\n<p>Es m\u00e1s, la responsabilidad por tal conducta \u00a0punible, \u00a0como \u00a0el \u00a0mismo demandante lo indica, no se ha determinado y es objeto \u00a0de \u00a0una \u00a0actuaci\u00f3n \u00a0en curso, luego incurre el censor en petici\u00f3n de principio \u00a0porque \u00a0con ello da por sentado precisamente lo que pretende demostrar, esto es, \u00a0que \u00a0Pe\u00f1a \u00a0Mosquera \u00a0fue el \u00a0autor \u00a0del \u00a0delito \u00a0de \u00a0acceso carnal violento en la v\u00edctima y que la delaci\u00f3n \u00a0tuvo \u00a0por \u00a0objeto encubrirla, responsabilidad que se indaga en ese procesamiento \u00a0independiente. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0expuesto, estos cargos tambi\u00e9n se \u00a0inadmitir\u00e1n. \u00a0\u00a0<\/p>\n<p>En \u00a0suma, \u00a0las falencias destacadas de las \u00a0censuras \u00a0propuestas \u00a0por \u00a0el defensor de JHONY PARDO \u00a0DUARTE \u00a0conducen \u00a0a \u00a0la inadmisi\u00f3n de la demanda, en \u00a0atenci\u00f3n \u00a0a \u00a0lo normado en los art\u00edculos 183 y 184 de \u00a0la \u00a0Ley \u00a0906 de 2004, debiendo dejar en claro la Sala que ni del contenido de la \u00a0demanda, \u00a0ni \u00a0de \u00a0la \u00a0revisi\u00f3n \u00a0del \u00a0proceso \u00a0surge la necesidad de superar los \u00a0defectos \u00a0aludidos \u00a0en \u00a0procura \u00a0de \u00a0cumplir \u00a0alguno \u00a0de \u00a0los \u00a0fines del recurso \u00a0extraordinario \u00a0previstos \u00a0en el art\u00edculo 180 ib\u00eddem \u00a0o \u00a0que \u00a0haga imprescindible activar el mecanismo de la \u00a0casaci\u00f3n oficiosa.\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Por \u00faltimo, se\u00f1\u00e1lese que habida cuenta de \u00a0que \u00a0contra \u00a0la decisi\u00f3n de inadmitir la demanda de casaci\u00f3n presentada por la \u00a0defensa \u00a0procede \u00a0el \u00a0mecanismo de insistencia de conformidad con lo establecido \u00a0en \u00a0el \u00a0art\u00edculo \u00a0184 \u00a0de \u00a0la \u00a0Ley \u00a0906 de 2004, impera precisar que como dicha \u00a0legislaci\u00f3n \u00a0no \u00a0regula \u00a0el \u00a0tr\u00e1mite \u00a0a seguir para que se aplique el referido \u00a0instituto \u00a0procesal, \u00a0la \u00a0Sala \u00a0ha \u00a0definido \u00a0las reglas que habr\u00e1n de seguirse \u00a0sobre \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0particular7. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0En \u00a0m\u00e9rito \u00a0de lo expuesto, la CORTE SUPREMA DE JUSTICIA, SALA DE \u00a0CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0INADMITIR \u00a0 la \u00a0 demanda \u00a0 de \u00a0 casaci\u00f3n \u00a0presentada \u00a0por \u00a0el defensor \u00a0de \u00a0JHONY PARDO DUARTE, por \u00a0las razones consignadas en la anterior motivaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0De \u00a0 conformidad \u00a0con \u00a0lo \u00a0dispuesto \u00a0en \u00a0el \u00a0inciso \u00a0segundo \u00a0del \u00a0art\u00edculo \u00a0184 \u00a0de \u00a0la Ley 906 de\u00a0 2004 y, en los t\u00e9rminos referidos en el \u00a0ac\u00e1pite \u00a0final \u00a0de \u00a0esta \u00a0determinaci\u00f3n, \u00a0contra \u00a0esta \u00a0decisi\u00f3n \u00a0procede \u00a0la \u00a0insistencia. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>JOS\u00c9 \u00a0 \u00a0 LEONIDAS \u00a0 \u00a0BUSTOS MART\u00cdNEZ \u00a0\u00a0<\/p>\n<p>JOS\u00c9 \u00a0LUIS \u00a0BARCEL\u00d3 \u00a0CAMACHO\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0FERNANDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 ALBERTO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CASTRO \u00a0CABALLERO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>SIGIFREDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ESPINOSA \u00a0P\u00c9REZ\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0MAR\u00cdA \u00a0 DEL \u00a0 ROSARIO \u00a0GONZ\u00c1LEZ \u00a0MU\u00d1OZ\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0IMPEDIDO \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>AUGUSTO \u00a0J. \u00a0IB\u00c1\u00d1EZ \u00a0GUZM\u00c1N\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 LUIS \u00a0 GUILLERMO \u00a0SALAZAR OTERO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JULIO \u00a0 \u00a0 \u00a0 \u00a0E. \u00a0 \u00a0 \u00a0 \u00a0SOCHA \u00a0SALAMANCA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0JAVIER \u00a0 \u00a0 ZAPATA \u00a0ORT\u00cdZ \u00a0\u00a0<\/p>\n<p>NUBIA \u00a0YOLANDA \u00a0NOVA \u00a0GARC\u00cdA \u00a0\u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 De 8 \u00a0a\u00f1os para el momento de los hechos. \u00a0\u00a0<\/p>\n<p>2 Cfr. \u00a0entre \u00a0otras \u00a0sentencias \u00a0de \u00a0noviembre \u00a018 de 2008, rad. 30539 y de marzo 18 de \u00a02009, rad. 30710. \u00a0\u00a0<\/p>\n<p>3 Copia \u00a0de \u00a0la \u00a0sentencia \u00a0obra \u00a0a \u00a0folio \u00a0248 \u00a0de \u00a0la \u00a0carpeta de la causa.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>4 \u00a0Sentencia \u00a0de \u00a0noviembre \u00a026 \u00a0de \u00a02003, \u00a0rad. \u00a015962.\u00a0 \u00a0Tambi\u00e9n \u00a0se \u00a0puede \u00a0consultar \u00a0m\u00e1s \u00a0recientemente \u00a0sobre \u00a0el \u00a0mimo \u00a0tema, sentencia de agosto 31 de \u00a02011, rad. 31761. \u00a0\u00a0<\/p>\n<p>5 \u00a0Decisi\u00f3n \u00a0de \u00a0septiembre \u00a017 \u00a0de \u00a02008, \u00a0rad. 29901; en el mismo \u00a0sentido, \u00a0decisi\u00f3n \u00a0de \u00a0la \u00a0misma fecha rad. 30299; de octubre 17 de octubre de \u00a02007, rad. 28451 y de septiembre 12 del mismo a\u00f1o rad. 28080. \u00a0\u00a0<\/p>\n<p>6 \u00a0Sentencia de octubre 10 de 2007, rad. 28212. \u00a0\u00a0<\/p>\n<p>7 \u00a0Providencia del 12 de diciembre de 2005. Rad. 24322. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso n\u00ba 37952 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrada Ponente: \u00a0 MARIA \u00a0DEL \u00a0ROSARIO \u00a0GONZ\u00c1LEZ \u00a0MU\u00d1OZ Aprobado Acta No. 139. \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Bogot\u00e1, \u00a0D. \u00a0C., abril dieciocho (18) de dos \u00a0mil doce (2012). \u00a0\u00a0 VISTOS \u00a0 Se pronuncia la Corte sobre la admisibilidad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-24223","post","type-post","status-publish","format-standard","hentry","category-20"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/24223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=24223"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/24223\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=24223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=24223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=24223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}