{"id":24145,"date":"2023-09-12T17:21:34","date_gmt":"2023-09-12T17:21:34","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3782611-04-12\/"},"modified":"2023-09-12T17:21:34","modified_gmt":"2023-09-12T17:21:34","slug":"3782611-04-12","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3782611-04-12\/","title":{"rendered":"37826(11-04-12)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso n\u00ba 37826 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CORTE SUPREMA DE JUSTICIA \u00a0\u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>JAVIER ZAPATA ORTIZ \u00a0<\/p>\n<p>Aprobado \u00a0 \u00a0Acta \u00a0 \u00a0No. \u00a0 \u00a0121 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Bogot\u00e1 \u00a0D. C., once (11) de abril de dos \u00a0mil doce (2012) \u00a0\u00a0<\/p>\n<p>VISTOS: \u00a0\u00a0<\/p>\n<p>Surtido \u00a0 el \u00a0traslado \u00a0previsto \u00a0por \u00a0el \u00a0art\u00edculo \u00a0500 \u00a0del \u00a0C\u00f3digo de Procedimiento Penal, Ley 906 de 2004, la Sala de \u00a0Casaci\u00f3n \u00a0Penal \u00a0emite \u00a0concepto \u00a0relativo \u00a0a \u00a0la \u00a0extradici\u00f3n \u00a0del \u00a0ciudadano \u00a0colombiano \u00a0MIGUEL \u00a0ANTONIO \u00a0MONROY \u00a0RAM\u00cdREZ, \u00a0requerido en extradici\u00f3n por el \u00a0Gobierno \u00a0de \u00a0los Estados Unidos de Am\u00e9rica, para que \u00a0comparezca \u00a0 a \u00a0 juicio \u00a0 por \u00a0 delitos \u00a0 federales \u00a0de \u00a0narc\u00f3ticos. \u00a0\u00a0<\/p>\n<p>ANTECEDENTES: \u00a0\u00a0<\/p>\n<p>1. \u00a0 Con \u00a0Nota \u00a0Verbal \u00a0No. \u00a01986 \u00a0 \u00a0 \u00a0del \u00a0 \u00a0 \u00a018 \u00a0 \u00a0 de \u00a0 \u00a0 agosto \u00a0 \u00a0 de \u00a0 \u00a0 2011, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la \u00a0Embajada \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica \u00a0en \u00a0nuestro pa\u00eds solicit\u00f3 la detenci\u00f3n \u00a0provisional \u00a0con \u00a0fines de extradici\u00f3n del colombiano \u00a0MIGUEL \u00a0 \u00a0ANTONIO \u00a0 MONROY \u00a0 RAM\u00cdREZ \u00a0 alias \u00a0 \u201cMitchell\u201d, \u00a0 \u201cBarbas\u201d, \u00a0\u201cOj\u00f3n\u201d, \u00a0 \u00a0 \u00a0 \u201cViejo\u201d \u00a0 \u00a0 \u00a0identificado \u00a0 \u00a0con \u00a0 \u00a0la \u00a0 c\u00e9dula \u00a0 No. \u00a0 19\u00b4118.606, \u00a0 \u00a0 \u00a0 requerido \u00a0 \u00a0 \u00a0para \u00a0 \u00a0comparecer \u00a0 \u00a0a \u00a0 juicio \u00a0 \u00a0 por \u00a0 \u00a0delitos \u00a0 \u00a0federales \u00a0de \u00a0narc\u00f3ticos, de acuerdo \u00a0con \u00a0 los \u00a0 cargos \u00a0 atribuidos \u00a0 en \u00a0la \u00a0Acusaci\u00f3n \u00a0Formal \u00a0de \u00a0Reemplazo \u00a0No. \u00a010-20798-CR-COOKE(s) \u00a0dictada el 7 de junio de 2011 en la Corte Distrital de los \u00a0Estados \u00a0Unidos \u00a0para \u00a0el \u00a0Distrito \u00a0Sur \u00a0de Florida1. \u00a0\u00a0<\/p>\n<p>2. \u00a0 Del \u00a0anterior \u00a0documento \u00a0el Ministerio de Relaciones Exteriores \u00a0remiti\u00f3 \u00a0 \u00a0 \u00a0 copia \u00a0 \u00a0 \u00a0 al \u00a0 \u00a0 \u00a0 Fiscal \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0quien \u00a0con \u00a0resoluci\u00f3n \u00a0del 29 de \u00a0agosto \u00a0de \u00a02011 \u00a0orden\u00f3 \u00a0la \u00a0captura, \u00a0decisi\u00f3n \u00a0que se hizo efectiva el 1 de \u00a0septiembre \u00a0siguiente \u00a0por \u00a0miembros de la Polic\u00eda Nacional. \u00a0\u00a0<\/p>\n<p>3. La Embajada de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica, \u00a0con \u00a0Nota Verbal \u00a0No. \u00a02677 \u00a0del \u00a027 \u00a0de \u00a0octubre \u00a0de \u00a02011, \u00a0 \u00a0formaliz\u00f3 \u00a0 \u00a0la \u00a0 \u00a0solicitud \u00a0 \u00a0de \u00a0 extradici\u00f3n \u00a0adjuntando la documentaci\u00f3n requerida, traducida y legalizada de \u00a0acuerdo \u00a0con \u00a0lo \u00a0dispuesto \u00a0en la materia por el C\u00f3digo de Procedimiento Penal \u00a0Colombiano. \u00a0\u00a0<\/p>\n<p>4. \u00a0Los \u00a0documentos \u00a0remitidos por el gobierno \u00a0de \u00a0Estados \u00a0Unidos \u00a0para \u00a0sustentar \u00a0el \u00a0pedido \u00a0de \u00a0extradici\u00f3n \u00a0son: \u00a0\u00a0<\/p>\n<p>4.1 \u00a0Copia \u00a0de \u00a0la \u00a0Acusaci\u00f3n \u00a0Formal \u00a0de \u00a0Reemplazo \u00a0No. \u00a010-20798-CR-COOKE(s) \u00a0dictada \u00a0el 7 de junio de 2011 en la Corte \u00a0Distrital \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0para el Distrito Sur de Florida2 \u00a0donde le formulan los siguientes cargos: \u00a0\u00a0<\/p>\n<p>\u201c&#8211; \u00a0 Cargo \u00a0uno: \u00a0 Concierto \u00a0para \u00a0fabricar \u00a0y \u00a0distribuir \u00a0una \u00a0sustancia \u00a0controlada \u00a0(cinco kilogramos o m\u00e1s de coca\u00edna) con el conocimiento \u00a0de \u00a0que dicha sustancia controlada iba a ser importada ilegalmente a los Estados \u00a0Unidos, \u00a0 \u00a0lo \u00a0 \u00a0cual \u00a0 es \u00a0 en \u00a0 contra \u00a0 del \u00a0 T\u00edtulo \u00a0 21,\u00a0 \u00a0 Secciones \u00a0959(a)(2)\u00a0\u00a0 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0los \u00a0Estados \u00a0Unidos, en violaci\u00f3n del \u00a0T\u00edtulo \u00a021, \u00a0Secciones \u00a0963\u00a0 \u00a0y \u00a0960(b)(1)(B) \u00a0del \u00a0c\u00f3digo de los Estados \u00a0Unidos. \u00a0\u00a0<\/p>\n<p>\u201cCargo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dos: \u00a0 \u00a0 Fabricar \u00a0 \u00a0 y \u00a0 \u00a0 distribuir \u00a0una \u00a0sustancia controlada \u00a0(cinco \u00a0kilogramos \u00a0o \u00a0m\u00e1s \u00a0de \u00a0coca\u00edna), \u00a0con \u00a0el \u00a0conocimiento \u00a0de que dicha \u00a0sustancia \u00a0controlada \u00a0iba \u00a0a \u00a0ser importada ilegalmente a los Estados Unidos, y \u00a0ayuda \u00a0 y \u00a0 facilitaci\u00f3n \u00a0 de \u00a0 dicho \u00a0delito, \u00a0en \u00a0violaci\u00f3n \u00a0del \u00a0T\u00edtulo \u00a021, \u00a0Secciones 959(a)(2) y \u00a0960(b)(1)(B) \u00a0del \u00a0c\u00f3digo \u00a0de \u00a0los \u00a0Estados \u00a0Unidos, y del T\u00edtulo 18, Secci\u00f3n \u00a02\u00a0 del C\u00f3digo de los Estados Unidos. \u00a0\u00a0<\/p>\n<p>\u201cCargo \u00a0tres: \u00a0Concierto \u00a0para \u00a0poseer \u00a0sustancia \u00a0 controlada \u00a0(cinco \u00a0kilogramos \u00a0o \u00a0m\u00e1s \u00a0de \u00a0coca\u00edna) \u00a0con \u00a0la \u00a0intenci\u00f3n de distribuirla, \u00a0mientras \u00a0se \u00a0encontraba \u00a0a \u00a0bordo \u00a0de \u00a0un \u00a0avi\u00f3n \u00a0de matr\u00edcula de los Estados \u00a0Unidos, \u00a0lo cual es en contra del t\u00edtulo 21, Secci\u00f3n 959 (b)(2) del C\u00f3digo de \u00a0los \u00a0Estados \u00a0unidos, en violaci\u00f3n del t\u00edtulo 21, Secciones 963 y 960(b)(1)(B) \u00a0del c\u00f3digo de los Estados Unidos. \u00a0\u00a0<\/p>\n<p>4.2. \u00a0Declaraci\u00f3n \u00a0 jurada \u00a0 rendida \u00a0 el \u00a0 14 \u00a0de octubre de 2011 por Andrea \u00a0G. Hoffman, Fiscal Federal \u00a0 \u00a0 Auxiliar \u00a0 \u00a0en \u00a0 \u00a0el \u00a0 \u00a0Distrito \u00a0 \u00a0Judicial \u00a0 del \u00a0 Sur \u00a0de \u00a0la \u00a0Florida, \u00a0donde \u00a0 \u00a0 refiri\u00f3 \u00a0el \u00a0 procedimiento \u00a0cumplido \u00a0por \u00a0el \u00a0Gran \u00a0 \u00a0 \u00a0Jurado \u00a0 \u00a0 para \u00a0dictar la acusaci\u00f3n, present\u00f3 una \u00a0s\u00edntesis \u00a0de \u00a0los \u00a0hechos \u00a0que \u00a0dieron \u00a0lugar \u00a0a \u00a0la solicitud de extradici\u00f3n, \u00a0concret\u00f3 \u00a0 los \u00a0cargos \u00a0formulados \u00a0contra \u00a0MIGUEL \u00a0ANTONIO \u00a0 \u00a0 \u00a0MONROY \u00a0 \u00a0 RAM\u00cdREZ \u00a0 \u00a0 alias \u00a0 \u201cMitchell\u201d, \u00a0\u201cBarbas\u201d, \u00a0\u201cOj\u00f3n\u201d, \u00a0 \u00a0\u201cViejo\u201d, \u00a0 precis\u00f3 \u00a0los \u00a0elementos \u00a0integrantes \u00a0de \u00a0cada \u00a0delito \u00a0y aport\u00f3 \u00a0 los \u00a0 datos \u00a0 allegados \u00a0a \u00a0la \u00a0investigaci\u00f3n \u00a0 \u00a0 sobre \u00a0 \u00a0la \u00a0 \u00a0identidad \u00a0 \u00a0del \u00a0requerido \u00a0(folio \u00a0196 \u00a0 \u00a0carpeta \u00a0 \u00a0 \u00a0 \u00a0 \u00a0anexa). \u00a0\u00a0<\/p>\n<p>4.3. \u00a0Declaraci\u00f3n \u00a0 \u00a0jurada \u00a0 \u00a0rendida \u00a0 el \u00a014 de octubre de 2011 por Jeremy Eric \u00a0Jones, \u00a0 \u00a0 Agente \u00a0Especial \u00a0del Servicio de los EE.UU. para el control \u00a0de \u00a0Drogas \u00a0(DEA), \u00a0quien \u00a0proporcion\u00f3 informaci\u00f3n \u00a0adicional \u00a0sobre la investigaci\u00f3n, actividad, manera \u00a0de \u00a0operar \u00a0de \u00a0la organizaci\u00f3n criminal e identidad \u00a0del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 acusado \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(folio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 263 \u00a0carpeta\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0anexa). \u00a0\u00a0<\/p>\n<p>4.4. \u00a0 \u00a0 \u00a0 \u00a0Transcripci\u00f3n \u00a0de \u00a0las disposiciones penales sustantivas supuestamente \u00a0vulneradas \u00a0 \u00a0 por \u00a0 \u00a0 el \u00a0 \u00a0requerido \u00a0en extradici\u00f3n con las conductas que \u00a0se \u00a0 \u00a0 \u00a0 \u00a0le \u00a0 \u00a0 \u00a0 atribuyen \u00a0 \u00a0 \u00a0 (folio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0210 \u00a0 \u00a0 \u00a0 \u00a0a \u00a0 \u00a0 \u00a0 217carpeta \u00a0anexa). \u00a0\u00a0<\/p>\n<p>4.5. \u00a0Copia de \u00a0Consulta \u00a0 \u00a0 T\u00e9cnica \u00a0 \u00a0a \u00a0 \u00a0la \u00a0 \u00a0Registradur\u00eda \u00a0 \u00a0Nacional \u00a0 \u00a0del Estado Civil donde se estableci\u00f3 la \u00a0identificaci\u00f3n \u00a0de \u00a0MIGUEL \u00a0ANTONIO MONROY RAM\u00cdREZ, \u00a0ciudadano \u00a0colombiano \u00a0nacido \u00a0el 13 de junio de \u00a01950, \u00a0portador \u00a0de \u00a0la \u00a0c\u00e9dula \u00a0de ciudadan\u00eda No. \u00a019.118.606 \u00a0(folio \u00a0 \u00a0 \u00a0 295 \u00a0 \u00a0 \u00a0 carpeta \u00a0 \u00a0 \u00a0 \u00a0 \u00a0anexa). \u00a0\u00a0<\/p>\n<p>4.6. \u00a0Copia \u00a0de \u00a0la orden de arresto \u00a0emitida \u00a0el 7 de junio de 2011 \u00a0por \u00a0el \u00a0Tribunal \u00a0de Distrito de los Estados Unidos \u00a0para \u00a0 \u00a0el \u00a0 Sur \u00a0 de \u00a0Florida\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(folio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 234 carpeta anexa). \u00a0\u00a0<\/p>\n<p>5. El Ministerio \u00a0del \u00a0Interior \u00a0y \u00a0de Justicia estim\u00f3 que el expediente se encontraba completo y \u00a0la \u00a0 \u00a0 \u00a0 solicitud \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0extradici\u00f3n \u00a0 \u00a0 \u00a0formalizada, \u00a0 \u00a0 \u00a0disponiendo \u00a0su \u00a0env\u00edo \u00a0a \u00a0la Sala de \u00a0Casaci\u00f3n \u00a0 \u00a0Penal \u00a0 de \u00a0 la \u00a0 Corte \u00a0 para \u00a0 \u00a0 \u00a0 \u00a0lo \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0su \u00a0 \u00a0 \u00a0 \u00a0competencia.\u00a0 \u00a0Adjunt\u00f3 \u00a0el \u00a0concepto rendido \u00a0por \u00a0 el \u00a0 Jefe \u00a0 de \u00a0 la \u00a0 Oficina \u00a0 Jur\u00eddica \u00a0 del \u00a0 Ministerio \u00a0de \u00a0 \u00a0 Relaciones \u00a0 \u00a0Exteriores \u00a0atinente \u00a0a \u00a0la \u00a0aplicaci\u00f3n \u00a0de \u00a0la \u00a0legislaci\u00f3n penal \u00a0colombiana, \u00a0 \u00a0al \u00a0 no \u00a0existir \u00a0 tratado \u00a0 de \u00a0 extradici\u00f3n \u00a0en \u00a0 vigor \u00a0 entre \u00a0Estados \u00a0Unidos \u00a0y \u00a0Colombia. \u00a0\u00a0<\/p>\n<p>6. Garantizado \u00a0por \u00a0la \u00a0Corte el derecho a la defensa de \u00a0 MIGUEL \u00a0ANTONIO \u00a0MONROY \u00a0RAM\u00cdREZ, \u00a0el \u00a0defensor \u00a0y \u00a0el procurador acogieron \u00a0lo \u00a0dispuesto en el art\u00edculo 70 de la Ley 1453 de 2011 sobre el \u00a0tr\u00e1mite \u00a0de \u00a0\u201cextradici\u00f3n \u00a0simplificada\u201d, \u00a0del \u00a0cual \u00a0 \u00a0 \u00a0 previamente \u00a0 \u00a0 \u00a0 se \u00a0 \u00a0 \u00a0inform\u00f3 \u00a0 \u00a0 \u00a0al \u00a0 \u00a0 \u00a0requerido, \u00a0 quien \u00a0 de \u00a0 manera \u00a0libre \u00a0 \u00a0y \u00a0 \u00a0voluntaria \u00a0 \u00a0 expres\u00f3 \u00a0 \u00a0el \u00a0 \u00a0conocimiento \u00a0acerca \u00a0de \u00a0las \u00a0consecuencias \u00a0de su renuncia a la \u00a0aplicaci\u00f3n \u00a0del \u00a0art\u00edculo \u00a0500 \u00a0de \u00a0la \u00a0Ley 906 de \u00a02004. \u00a0\u00a0<\/p>\n<p>El \u00a0Ministerio P\u00fablico se\u00f1al\u00f3 \u00a0 que \u00a0 los \u00a0 delitos \u00a0 atribuidos \u00a0a \u00a0MONROY \u00a0RAM\u00cdREZ \u00a0fueron \u00a0cometidos \u00a0 \u00a0 con \u00a0posterioridad \u00a0a la expedici\u00f3n del acto legislativo No. 1 de 1997, no tienen la \u00a0connotaci\u00f3n \u00a0de \u00a0pol\u00edticos \u00a0y \u00a0tambi\u00e9n est\u00e1n contemplados en la legislaci\u00f3n \u00a0penal \u00a0colombiana, por lo cual concluy\u00f3 como cumplidos los requisitos legales y \u00a0constitucionales \u00a0de \u00a0la \u00a0extradici\u00f3n \u00a0simplificada \u00a0para \u00a0que \u00a0la \u00a0Sala \u00a0emita \u00a0concepto de plano.\u00a0 \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE \u00a0LA \u00a0SALA \u00a0\u00a0<\/p>\n<p>1. Cuestiones Previas \u00a0<\/p>\n<p>Debido a que no \u00a0existe \u00a0tratado \u00a0de \u00a0extradici\u00f3n aplicable entre los \u00a0Estados \u00a0Unidos \u00a0y \u00a0Colombia, \u00a0seg\u00fan lo inform\u00f3 el \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores, \u00a0y \u00a0dado que \u00a0los hechos ocurrieron con \u00a0posterioridad \u00a0al \u00a017 \u00a0de diciembre de 1997, espec\u00edficamente entre abril \u00a0 de \u00a0 2009 \u00a0 hasta \u00a0 la \u00a0 fecha \u00a0 de \u00a0 la \u00a0emisi\u00f3n \u00a0de \u00a0la \u00a0acusaci\u00f3n, \u00a0este \u00a0tr\u00e1mite se rige por la \u00a0 \u00a0 Ley \u00a0 \u00a0 906 \u00a0 \u00a0 de \u00a0 \u00a0 20043. \u00a0\u00a0<\/p>\n<p>La Sala emitir\u00e1 \u00a0concepto \u00a0favorable \u00a0a la extradici\u00f3n del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ciudadano \u00a0MIGUEL \u00a0ANTONIO \u00a0MONROY RAM\u00cdREZ, pues se re\u00fanen \u00a0 \u00a0 \u00a0 \u00a0 los \u00a0 \u00a0 \u00a0 \u00a0requisitos \u00a0 \u00a0legales \u00a0 exigidos \u00a0 \u00a0en \u00a0 el \u00a0 art\u00edculo \u00a0 502 \u00a0ib\u00eddem \u00a0 como \u00a0 son: \u00a0 validez \u00a0formal \u00a0de \u00a0la \u00a0documentaci\u00f3n \u00a0 \u00a0 \u00a0 presentada, \u00a0 \u00a0 \u00a0 plena \u00a0 \u00a0 \u00a0 identidad \u00a0 \u00a0 \u00a0del \u00a0 \u00a0 \u00a0 \u00a0 solicitado, \u00a0 \u00a0principio \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0doble \u00a0incriminaci\u00f3n, \u00a0 \u00a0equivalencia \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0providencia \u00a0 proferida \u00a0 en \u00a0 el \u00a0extranjero. \u00a0\u00a0<\/p>\n<p>2. \u00a0Validez \u00a0formal \u00a0de \u00a0la documentaci\u00f3n \u00a0presentada \u00a0\u00a0<\/p>\n<p>El \u00a0art\u00edculo \u00a0495 \u00a0de la Ley 906 de 2004, \u00a0dispone \u00a0que \u00a0para \u00a0conceder \u00a0u \u00a0ofrecer \u00a0la \u00a0extradici\u00f3n \u00a0de \u00a0una \u00a0persona, la \u00a0solicitud \u00a0debe \u00a0ser \u00a0presentada \u00a0por v\u00eda diplom\u00e1tica o en casos excepcionales \u00a0por \u00a0la consular o de gobierno a gobierno, adjuntando: i) copia o transcripci\u00f3n \u00a0aut\u00e9ntica \u00a0de \u00a0la \u00a0sentencia, de la resoluci\u00f3n de acusaci\u00f3n o su equivalente; \u00a0ii) \u00a0indicaci\u00f3n \u00a0exacta \u00a0de \u00a0los actos que determinaron la solicitud, y lugar y \u00a0fecha \u00a0en que fueron ejecutados; iii) todos los datos que sirvan para establecer \u00a0la \u00a0plena \u00a0identidad \u00a0de \u00a0la \u00a0persona \u00a0reclamada; \u00a0y iv) copia aut\u00e9ntica de las \u00a0disposiciones penales aplicables al caso. \u00a0\u00a0<\/p>\n<p>El Gobierno de los Estados Unidos cumpli\u00f3 \u00a0adecuadamente \u00a0tales \u00a0exigencias, \u00a0pues, \u00a0por \u00a0v\u00eda \u00a0diplom\u00e1tica, \u00a0present\u00f3 la \u00a0solicitud \u00a0a trav\u00e9s de su Embajada en nuestro pa\u00eds al Ministerio de Relaciones \u00a0Exteriores; \u00a0 anex\u00f3 \u00a0 copia \u00a0 de \u00a0 la \u00a0Acusaci\u00f3n \u00a0Formal \u00a0de \u00a0Reemplazo No. 10-20798-CR-COOKE(s) dictada \u00a0el \u00a07 \u00a0de \u00a0junio \u00a0de \u00a02011 \u00a0en \u00a0la Corte Distrital de los Estados Unidos para el \u00a0Distrito \u00a0 \u00a0 \u00a0Sur \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 la \u00a0 \u00a0 Florida4 \u00a0 \u00a0 \u00a0 \u00a0 contra \u00a0 \u00a0MIGUEL \u00a0 \u00a0ANTONIO \u00a0 MONROY \u00a0RAM\u00cdREZ \u00a0 por \u00a0delitos \u00a0federales de narc\u00f3ticos. \u00a0\u00a0<\/p>\n<p>Igualmente \u00a0con \u00a0notas \u00a0diplom\u00e1ticas \u00a0la \u00a0Embajada \u00a0formaliz\u00f3 \u00a0la \u00a0reclamaci\u00f3n, \u00a0apoyado en los testimonios rendidos por \u00a0Andrea\u00a0 \u00a0 \u00a0 \u00a0 G. \u00a0 \u00a0 \u00a0 Hoffman, \u00a0 \u00a0Fiscal \u00a0 \u00a0Auxiliar \u00a0de \u00a0los Estados Unidos\u00a0 para el \u00a0Distrito Sur de Florida y \u00a0Jeremy Eric Jones, \u00a0Agente \u00a0Especial \u00a0de \u00a0la \u00a0Oficina \u00a0de \u00a0control \u00a0de \u00a0Drogas \u00a0DEA, \u00a0quienes \u00a0determinaron \u00a0las \u00a0circunstancias \u00a0de \u00a0modo, \u00a0tiempo \u00a0y \u00a0lugar de realizaci\u00f3n de los \u00a0delitos \u00a0y \u00a0su incidencia \u00a0en \u00a0el pa\u00eds requirente, cumpliendo de esta manera la exigencia del art\u00edculo 35 \u00a0de \u00a0la Constituci\u00f3n Pol\u00edtica, consistente en que la extradici\u00f3n se conceder\u00e1 \u00a0por delitos cometidos en el exterior. \u00a0\u00a0<\/p>\n<p>Magdalena \u00a0A. Boyton Directora Asociada de \u00a0la \u00a0Oficina \u00a0de \u00a0Asuntos Internacionales, Divisi\u00f3n de lo Penal, Departamento de \u00a0Justicia \u00a0de los Estados Unidos, certific\u00f3 que copias fieles de los testimonios \u00a0antes \u00a0mencionados \u00a0se \u00a0mantienen \u00a0en los archivos oficiales del Departamento de \u00a0Justicia \u00a0 de \u00a0 los \u00a0 Estados \u00a0 Unidos \u00a0(folio\u00a0 \u00a066 \u00a0 carpeta \u00a0 anexa). \u00a0\u00a0<\/p>\n<p>El \u00a0Procurador de los Estados Unidos, Eric \u00a0H. \u00a0Holder \u00a0Jr., \u00a0hizo \u00a0constar \u00a0que \u00a0para \u00a0ese \u00a0entonces, \u00a0Magdalena A. Boyton, \u00a0desempe\u00f1aba \u00a0 el \u00a0 cargo \u00a0de \u00a0Directora \u00a0Asociada \u00a0de \u00a0la \u00a0Oficina \u00a0de \u00a0Asuntos \u00a0Internacionales \u00a0de la Divisi\u00f3n de lo Penal del Departamento de Justicia de los \u00a0Estados \u00a0Unidos \u00a0en \u00a0Washington D.C., quien con ese prop\u00f3sito estamp\u00f3 el sello \u00a0del \u00a0Departamento \u00a0de \u00a0Justicia y solicit\u00f3 al Director Adjunto de la Oficina de \u00a0Asuntos \u00a0Internacionales, \u00a0Divisi\u00f3n \u00a0de \u00a0lo \u00a0Penal \u00a0que \u00a0diera \u00a0fe \u00a0de su firma \u00a0(folio \u00a0 65 carpeta anexa). \u00a0\u00a0<\/p>\n<p>La Secretaria de \u00a0Estado, \u00a0 Hillary \u00a0 Rodham \u00a0Clinton \u00a0a \u00a0trav\u00e9s \u00a0del \u00a0Funcionario \u00a0 Auxiliar \u00a0 de \u00a0 Autenticaciones \u00a0 del \u00a0Departamento de Justicia \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica, Patrick \u00a0 \u00a0O. \u00a0 Hatchett, \u00a0certific\u00f3 que al documento anexo se \u00a0le \u00a0 \u00a0 \u00a0fij\u00f3 \u00a0 \u00a0 \u00a0el \u00a0 \u00a0 sello \u00a0 \u00a0 del \u00a0 \u00a0 Departamento \u00a0 \u00a0 de \u00a0 \u00a0 Estado, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(folio \u00a0 \u00a0 \u00a0 \u00a0 \u00a064 \u00a0 \u00a0 carpeta \u00a0 \u00a0anexa). \u00a0\u00a0<\/p>\n<p>La C\u00f3nsul de Colombia en Washington, Libia \u00a0Mosquera \u00a0 \u00a0 \u00a0Viveros, \u00a0 \u00a0 \u00a0refrend\u00f3 \u00a0 la \u00a0 autenticidad \u00a0 de \u00a0 \u00a0la \u00a0 \u00a0firma \u00a0 \u00a0de \u00a0 \u00a0Patrick \u00a0 O. \u00a0Hatchett, \u00a0y \u00a0 \u00a0 \u00a0a \u00a0 \u00a0 \u00a0su \u00a0 \u00a0 \u00a0vez \u00a0 \u00a0 la \u00a0 \u00a0 firma \u00a0 \u00a0 de \u00a0 \u00a0 aquella funcionaria fue abonada por el \u00a0Jefe \u00a0de \u00a0Autenticaciones \u00a0del \u00a0Ministerio de Relaciones Exteriores (folio \u00a062 \u00a0carpeta anexa). \u00a0\u00a0<\/p>\n<p>Los \u00a0 mencionados \u00a0 documentos \u00a0 fueron \u00a0traducidos \u00a0 al \u00a0 castellano \u00a0 por \u00a0 la \u00a0 Embajada \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>De esta manera se cumpli\u00f3 con lo dispuesto \u00a0en \u00a0el \u00a0art\u00edculo \u00a0259 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento Civil, modificado por el \u00a0art\u00edculo \u00a01\u00ba, numeral 118 del Decreto 2282 de 1989 de nuestra legislaci\u00f3n que \u00a0estipula: \u00a0\u201cLos \u00a0documentos p\u00fablicos otorgados en \u00a0el \u00a0pa\u00eds \u00a0extranjero \u00a0por funcionario de \u00e9ste o con su intervenci\u00f3n, deber\u00e1n \u00a0presentarse \u00a0debidamente autenticados por el c\u00f3nsul o agente diplom\u00e1tico de la \u00a0Rep\u00fablica, \u00a0y \u00a0en su defecto por el de una naci\u00f3n amiga, lo cual hace presumir \u00a0que \u00a0se otorgaron conforme a la ley del respectivo pa\u00eds. La firma del c\u00f3nsul o \u00a0agente \u00a0 diplom\u00e1tico \u00a0 se \u00a0 abonar\u00e1 \u00a0por \u00a0el\u00a0 \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores \u00a0de \u00a0Colombia, y si se trata de agentes consulares de un pa\u00eds amigo, \u00a0se \u00a0autenticar\u00e1 \u00a0previamente \u00a0por \u00a0el funcionario competente del mismo y los de \u00a0\u00e9ste por el C\u00f3nsul colombiano.\u201d \u00a0\u00a0<\/p>\n<p>Por \u00a0tanto \u00a0se \u00a0satisface \u00a0el requisito de \u00a0validez \u00a0 formal \u00a0 de \u00a0 la \u00a0 documentaci\u00f3n \u00a0 presentada \u00a0con \u00a0la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n. \u00a0\u00a0<\/p>\n<p>3. Demostraci\u00f3n plena de la identidad del \u00a0solicitado \u00a0\u00a0<\/p>\n<p>De \u00a0la \u00a0informaci\u00f3n \u00a0aportada \u00a0para \u00a0el \u00a0presente \u00a0tr\u00e1mite, \u00a0la \u00a0Sala \u00a0concluye \u00a0que \u00a0MIGUEL \u00a0ANTONIO \u00a0MONROY \u00a0RAM\u00cdREZ, \u00a0ciudadano \u00a0 \u00a0 \u00a0 \u00a0 colombiano, \u00a0nacido el \u00a013 \u00a0de \u00a0junio \u00a0de \u00a01950, \u00a0portador \u00a0de \u00a0la c\u00e9dula de ciudadan\u00eda No. 19.118.606 \u00a0es la misma persona requerida por el Gobierno de los \u00a0Estados Unidos de Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>Aseveraci\u00f3n \u00a0 soportada \u00a0en \u00a0las \u00a0notas \u00a0diplom\u00e1ticas, \u00a0 los \u00a0 testimonios \u00a0 rendidos \u00a0 en \u00a0 apoyo \u00a0a \u00a0la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n, \u00a0el \u00a0informe \u00a0de \u00a0la \u00a0Fiscal\u00eda \u00a0sobre \u00a0la notificaci\u00f3n que se le \u00a0hiciera \u00a0 de \u00a0 los \u00a0 prop\u00f3sitos \u00a0 de \u00a0 extradici\u00f3n \u00a0 adelantados, \u00a0 el \u00a0cotejo \u00a0dactilosc\u00f3pico \u00a0y \u00a0la actitud asumida consistente en otorgar poder a un abogado \u00a0para que lo asistiera. \u00a0\u00a0<\/p>\n<p>4. \u00a0 \u00a0Principio \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0doble \u00a0incriminaci\u00f3n \u00a0\u00a0<\/p>\n<p>El numeral 1\u00b0 del art\u00edculo 493 de la Ley \u00a0906 \u00a0de \u00a02004, establece que para conceder u ofrecer la extradici\u00f3n se requiere \u00a0que \u00a0el \u00a0hecho \u00a0motivante \u00a0tambi\u00e9n est\u00e9 previsto en Colombia como delito y sea \u00a0reprimido \u00a0con \u00a0una \u00a0sanci\u00f3n \u00a0privativa \u00a0de \u00a0la \u00a0libertad \u00a0cuyo \u00a0m\u00ednimo no sea \u00a0inferior a cuatro (4) a\u00f1os. \u00a0\u00a0<\/p>\n<p>Dicho \u00a0presupuesto \u00a0se \u00a0cumple \u00a0frente \u00a0a \u00a0MIGUEL \u00a0 \u00a0ANTONIO \u00a0 \u00a0MONROY \u00a0 RAM\u00cdREZ \u00a0 en \u00a0 relaci\u00f3n \u00a0con \u00a0los \u00a0cargos \u00a0por \u00a0los \u00a0que \u00a0es \u00a0requerido, \u00a0por \u00a0cuanto \u00a0equivale \u00a0en \u00a0Colombia \u00a0 \u00a0a \u00a0 \u00a0los \u00a0 \u00a0delitos \u00a0 de \u00a0 concierto \u00a0para delinquir y \u00a0 \u00a0 \u00a0 \u00a0narcotr\u00e1fico.. \u00a0\u00a0<\/p>\n<p>La \u00a0Acusaci\u00f3n \u00a0Formal \u00a0de \u00a0Reemplazo \u00a0No. \u00a010-20798-CR-COOKE(s) \u00a0dictada el 7 de junio de 2011 en la Corte Distrital de los \u00a0Estados \u00a0Unidos \u00a0para \u00a0el \u00a0Distrito Sur de Florida le \u00a0atribuye: \u00a0\u00a0<\/p>\n<p>CARGO \u00a0 \u00a0 \u00a0 1 \u00a0\u00a0<\/p>\n<p>\u201cComenzando en abril de 2009 o alrededor \u00a0de \u00a0 ese \u00a0entonces, \u00a0siendo \u00a0la \u00a0fecha \u00a0exacta \u00a0desconocida \u00a0por \u00a0el \u00a0Jurado \u00a0de \u00a0Acusaci\u00f3n, \u00a0y \u00a0siguiendo realizando lo aducido hasta la fecha de emisi\u00f3n de la \u00a0acusaci\u00f3n \u00a0de \u00a0reemplazo, \u00a0en \u00a0el \u00a0pa\u00eds \u00a0de Colombia, Am\u00e9rica del Sur y otras \u00a0partes, \u00a0los \u00a0acusados \u00a0\u2026. \u00a0MIGUEL \u00a0ANTONIO MONROY \u00a0RAM\u00cdREZ\u00a0 \u00a0alias \u00a0\u201cMitchell\u201d, \u201cBarbas\u201d, \u00a0\u201cOj\u00f3n\u201d, \u00a0 \u201cViejo\u201d\u2026, \u00a0 a \u00a0sabiendas \u00a0e \u00a0intencionalmente \u00a0se \u00a0unieron, \u00a0conspiraron \u00a0se \u00a0confederaron\u00a0 acordaron entre s\u00ed y con personas conocidas \u00a0y \u00a0desconocidas \u00a0por \u00a0el \u00a0Jurado \u00a0de \u00a0Acusaci\u00f3n, para fabricar y distribuir una \u00a0sustancia \u00a0controlada \u00a0enumerada \u00a0en \u00a0la \u00a0Lista \u00a0II, \u00a0a \u00a0sabiendas \u00a0de que dicha \u00a0sustancia \u00a0se \u00a0importar\u00eda \u00a0il\u00edcitamente a los Estados Unidos en violaci\u00f3n del \u00a0art\u00edculo \u00a0959(a)(2) \u00a0del \u00a0T\u00edtulo \u00a021 \u00a0del \u00a0C\u00f3digo \u00a0Federal \u00a0 de \u00a0ese \u00a0pa\u00eds; \u00a0todo \u00a0lo \u00a0cual \u00a0est\u00e1 \u00a0en \u00a0violaci\u00f3n del articulo 963 del mismo T\u00edtulo y c\u00f3digo. \u00a0\u00a0<\/p>\n<p>De \u00a0acuerdo con el art\u00edculo 960(b)(1)(B) \u00a0del \u00a0 \u00a0 t\u00edtulo \u00a0 \u00a0 21 \u00a0 \u00a0del \u00a0 \u00a0C\u00f3digo \u00a0 \u00a0Federal \u00a0 \u00a0de \u00a0 \u00a0los \u00a0 \u00a0Estados \u00a0Unidos \u00a0se \u00a0aduce adem\u00e1s que \u00a0esta \u00a0violaci\u00f3n de la ley se trata de cinco (5) kilogramos o m\u00e1s de una mezcla \u00a0y sustancia que contiene una cantidad detectable de coca\u00edna. \u00a0\u00a0<\/p>\n<p>CARGO \u00a02 \u00a0\u00a0<\/p>\n<p>El \u00a0 \u00a0 25 \u00a0 \u00a0 de \u00a0 \u00a0 junio \u00a0de \u00a02009 \u00a0o \u00a0alrededor \u00a0de \u00a0esa \u00a0fecha, \u00a0en \u00a0el \u00a0pa\u00eds \u00a0de \u00a0Colombia, \u00a0Am\u00e9rica \u00a0del \u00a0Sur \u00a0y en otras partes, los \u00a0acusados \u00a0\u2026.MIGUEL \u00a0 ANTONIO \u00a0 MONROY \u00a0 RAM\u00cdREZ\u00a0 \u00a0alias \u00a0\u201cMitchell\u201d, \u00a0\u201cBarbas\u201d, \u00a0 \u00a0 \u00a0\u201cOj\u00f3n\u201d, \u00a0 \u00a0 \u00a0\u201cViejo\u201d\u2026, \u00a0 \u00a0 \u00a0a \u00a0 \u00a0 \u00a0sabiendas \u00a0 \u00a0 e \u00a0intencionalmente \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 fabricaron \u00a0y \u00a0distribuyeron una sustancia controlada enumerada en \u00a0la \u00a0Lista \u00a0II, a sabiendas de que dicha sustancia se importar\u00eda il\u00edcitamente a \u00a0los \u00a0Estaos \u00a0Unidos, \u00a0en \u00a0violaci\u00f3n \u00a0del art\u00edculo 959(a)(2) del t\u00edtulo 21 del \u00a0C\u00f3digo \u00a0Federal \u00a0de \u00a0ese \u00a0pa\u00eds \u00a0y \u00a0del \u00a0art\u00edculo \u00a02 \u00a0del T\u00edtulo 18 del mismo \u00a0c\u00f3digo. \u00a0\u00a0<\/p>\n<p>De \u00a0acuerdo con el art\u00edculo 960(b)(1)(B) \u00a0del \u00a0 \u00a0 t\u00edtulo \u00a0 \u00a0 21 \u00a0 \u00a0del \u00a0 \u00a0C\u00f3digo \u00a0 \u00a0Federal \u00a0 \u00a0de \u00a0 \u00a0los \u00a0 \u00a0\u2013estados Unidos se aduce adem\u00e1s que \u00a0esta \u00a0violaci\u00f3n de la ley se trata de cinco (5) kilogramos o m\u00e1s de una mezcla \u00a0y \u00a0sustancia \u00a0que \u00a0contiene \u00a0una \u00a0cantidad \u00a0detectable \u00a0de \u00a0coca\u00edna. \u00a0\u00a0<\/p>\n<p>CARGO \u00a03 \u00a0\u00a0<\/p>\n<p>\u201cComenzando en abril de 2009 o alrededor \u00a0de \u00a0 ese \u00a0entonces, \u00a0siendo \u00a0la \u00a0fecha \u00a0exacta \u00a0desconocida \u00a0por \u00a0el \u00a0Jurado \u00a0de \u00a0Acusaci\u00f3n, \u00a0y \u00a0siguiendo realizando lo aducido hasta la fecha de emisi\u00f3n de la \u00a0acusaci\u00f3n \u00a0de \u00a0reemplazo, \u00a0en \u00a0el \u00a0pa\u00eds \u00a0de Colombia, Am\u00e9rica del Sur y otras \u00a0partes, \u00a0los \u00a0acusados \u00a0\u2026. \u00a0MIGUEL \u00a0ANTONIO MONROY \u00a0RAM\u00cdREZ \u00a0 alias \u00a0 \u201cMitchell\u201d, \u00a0 \u201cBarbas\u201d, \u00a0\u201cOj\u00f3n\u201d, \u00a0 \u201cViejo\u201d\u2026, \u00a0 a \u00a0sabiendas \u00a0e \u00a0intencionalmente \u00a0se \u00a0unieron, \u00a0conspiraron \u00a0se \u00a0confederaron\u00a0 acordaron entre s\u00ed y con personas conocidas \u00a0y \u00a0 desconocidas \u00a0por \u00a0el \u00a0Jurado \u00a0de \u00a0Acusaci\u00f3n, \u00a0para \u00a0poseer \u00a0una \u00a0sustancia \u00a0controlada \u00a0con \u00a0la \u00a0intenci\u00f3n \u00a0de \u00a0distribuir\u00a0 \u00a0mientras se encontraban a \u00a0bordo \u00a0de \u00a0una \u00a0aeronave \u00a0con \u00a0matr\u00edcula \u00a0 \u00a0 de \u00a0 \u00a0los \u00a0 \u00a0Estados \u00a0 \u00a0Unidos, \u00a0en\u00a0 \u00a0violaci\u00f3n \u00a0del \u00a0art\u00edculo \u00a0959(a)(2) \u00a0del \u00a0T\u00edtulo \u00a0 \u00a0 21 \u00a0 \u00a0 del \u00a0 \u00a0C\u00f3digo \u00a0 \u00a0Federal \u00a0del \u00a0ese \u00a0pa\u00eds; \u00a0todo \u00a0lo \u00a0cual \u00a0est\u00e1 \u00a0en violaci\u00f3n del \u00a0articulo 963 del mismo T\u00edtulo y c\u00f3digo. \u00a0\u00a0<\/p>\n<p>De \u00a0acuerdo con el art\u00edculo 960(b)(1)(B) \u00a0del \u00a0 T\u00edtulo \u00a021 \u00a0del \u00a0C\u00f3digo \u00a0 \u00a0 Federal \u00a0 \u00a0de \u00a0 \u00a0los \u00a0 \u00a0Estados \u00a0Unidos \u00a0se \u00a0aduce adem\u00e1s que esta violaci\u00f3n de la ley se \u00a0trata \u00a0de cinco (5) kilogramos o m\u00e1s de una mezcla y sustancia que contiene una \u00a0cantidad \u00a0 \u00a0detectable \u00a0 de \u00a0 coca\u00edna. \u00a0\u00a0<\/p>\n<p>PRETENSIONES \u00a0 PARA \u00a0 LAEXTINCI\u00d3N \u00a0 DE \u00a0DOMINIO \u00a0\u00a0<\/p>\n<p>Las \u00a0pretensiones \u00a0 de \u00a0los \u00a0cargos \u00a01 \u00a0al \u00a04 \u00a0de la presente acusaci\u00f3n formal de \u00a0Reemplazo \u00a0se \u00a0vuelven \u00a0a \u00a0aducir y por referencia se \u00a0incorporan \u00a0 plenamente \u00a0 a \u00a0 la \u00a0 misma \u00a0 \u00a0 para \u00a0 \u00a0 pretender \u00a0la \u00a0extinci\u00f3n \u00a0de dominio a favor de \u00a0los \u00a0 \u00a0Estados \u00a0Unidos \u00a0de Am\u00e9rica de propiedad o propiedades en que los \u00a0acusados tengan participaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Al \u00a0declar\u00e1rseles culpables de cualquier \u00a0violaci\u00f3n \u00a0 \u00a0de \u00a0 \u00a0los \u00a0 \u00a0art\u00edculos \u00a0959(a), \u00a0959(b) \u00a0o 963 del t\u00edtulo 21 \u00a0del \u00a0 \u00a0c\u00f3digo \u00a0 \u00a0Federal \u00a0 \u00a0de \u00a0 \u00a0los \u00a0 Estados \u00a0 Unidos, \u00a0 los \u00a0 acusados \u00a0perder\u00e1n el dominio, el \u00a0cual \u00a0pasar\u00e1 a los Estados Unidos, de toda propiedad que constituya o se derive \u00a0del \u00a0 \u00a0 \u00a0producto \u00a0 \u00a0 obtenido, \u00a0 \u00a0 directa \u00a0 \u00a0 o \u00a0indirectamente \u00a0de tales \u00a0violaciones \u00a0y \u00a0de \u00a0toda \u00a0propiedad \u00a0 \u00a0 \u00a0 que \u00a0 \u00a0 \u00a0 los \u00a0 \u00a0 \u00a0acusados \u00a0 \u00a0 hayan \u00a0 \u00a0 usado \u00a0o \u00a0se \u00a0hayan \u00a0propuesto \u00a0usar \u00a0de \u00a0cualquier \u00a0manera \u00a0o \u00a0en \u00a0cualquier \u00a0 proporci\u00f3n \u00a0 para \u00a0 cometer \u00a0o \u00a0facilitar \u00a0la \u00a0comisi\u00f3n \u00a0de \u00a0tales \u00a0violaciones \u00a0de \u00a0la Ley. Todo lo cual de acuerdo con el art\u00edculo 853 del titulo \u00a021 del c\u00f3digo Federal de los Estados Unidos. \u00a0\u00a0<\/p>\n<p>El delito de concierto para infringir las \u00a0leyes \u00a0 \u00a0 antinarc\u00f3ticos \u00a0 \u00a0 en \u00a0 \u00a0los \u00a0 \u00a0Estados \u00a0Unidos atribuido a MIGUEL \u00a0ANTONIO \u00a0 \u00a0 MONROY \u00a0 \u00a0 RAM\u00cdREZ, \u00a0 \u00a0 es \u00a0tambi\u00e9n \u00a0punible \u00a0en \u00a0Colombia, \u00a0pues configura el injusto de \u00a0concierto \u00a0para delinquir \u00a0previsto \u00a0en el art\u00edculo 340 del C\u00f3digo Penal, Ley 599 de 2000, modificado por \u00a0el \u00a0art\u00edculo \u00a08\u00ba \u00a0de \u00a0la Ley 733 de 2002, cuyas penas fueron aumentadas por el \u00a0art\u00edculo \u00a014 \u00a0de \u00a0la \u00a0Ley \u00a0890 de 2004, quedando una sanci\u00f3n de 4 a 9 a\u00f1os de \u00a0prisi\u00f3n, \u00a0 para \u00a0 quienes \u00a0 se \u00a0concierten \u00a0con \u00a0el \u00a0fin \u00a0de \u00a0cometer \u00a0delitos. \u00a0\u00a0<\/p>\n<p>As\u00ed mismo, el inciso segundo de la citada \u00a0norma \u00a0fue \u00a0modificado por el art\u00edculo 19 de la Ley 1121 de 2006, en el sentido \u00a0de \u00a0establecer \u00a0una \u00a0pena \u00a0de \u00a08 \u00a0a \u00a018 \u00a0a\u00f1os \u00a0de \u00a0prisi\u00f3n \u00a0y multa de dos mil \u00a0setecientos \u00a0(2.700) hasta \u00a0treinta \u00a0 mil \u00a0 (30.000) \u00a0salarios \u00a0m\u00ednimos legales mensuales, cuando el acuerdo se dirija al tr\u00e1fico de \u00a0drogas \u00a0 t\u00f3xicas, \u00a0 estupefacientes \u00a0o \u00a0sustancias \u00a0psicotr\u00f3picas, \u00a0lavado \u00a0de \u00a0activos, entre otros.\u00a0 \u00a0\u00a0<\/p>\n<p>De \u00a0 igual \u00a0manera, \u00a0el \u00a0art\u00edculo \u00a0376 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0Ley \u00a0 \u00a0599 \u00a0 \u00a0de \u00a0 2000 \u00a0 modificado \u00a0 por \u00a0 la \u00a0 Ley \u00a01453 \u00a0de \u00a02011 \u00a0 \u00a0prev\u00e9 \u00a0 \u00a0y \u00a0 sanciona \u00a0 el \u00a0 tr\u00e1fico, \u00a0fabricaci\u00f3n \u00a0o \u00a0porte \u00a0de estupefacientes con \u00a0 pena \u00a0 de \u00a0 prisi\u00f3n \u00a0de \u00a0ciento \u00a0veintiocho \u00a0(128) a trescientos sesenta (360) meses y \u00a0multa \u00a0 \u00a0 \u00a0 de \u00a0 \u00a0 \u00a0 mil \u00a0 \u00a0 \u00a0 trescientos \u00a0 \u00a0 \u00a0treinta \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 \u00a0cuatro \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(1.334) \u00a0a \u00a0cincuenta \u00a0mil \u00a0(50.000) \u00a0 salarios \u00a0 m\u00ednimos \u00a0 legales \u00a0mensuales vigentes. \u00a0\u00a0<\/p>\n<p>En consecuencia, surge evidente que frente \u00a0a \u00a0estos \u00a0comportamientos converge la condici\u00f3n de ser delictivos en Colombia y \u00a0estar \u00a0sancionados \u00a0con \u00a0prisi\u00f3n \u00a0no menor de cuatro a\u00f1os, por tanto se cumple \u00a0con el principio de la doble incriminaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Respecto de la \u00a0extinci\u00f3n \u00a0de dominio planteada en la acusaci\u00f3n, la \u00a0cual \u00a0 \u00a0 busca \u00a0 \u00a0 la \u00a0 \u00a0incautaci\u00f3n \u00a0de \u00a0toda \u00a0ganancia \u00a0derivada \u00a0de las \u00a0actividades \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0tr\u00e1fico \u00a0 \u00a0 \u00a0 de \u00a0estupefacientes, \u00a0 es \u00a0preciso \u00a0se\u00f1alar \u00a0que \u00a0esta \u00a0menci\u00f3n \u00a0no \u00a0puede \u00a0ser entendida en estricto sentido como un cargo. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, \u00a0como \u00a0lo \u00a0ha \u00a0expresado esta \u00a0Corporaci\u00f3n \u00a0respecto \u00a0de \u00a0situaciones \u00a0semejantes5, \u00a0 \u00a0 \u00a0 \u00a0 el \u00a0se\u00f1alamiento \u00a0de \u00a0la extinci\u00f3n de \u00a0dominio \u00a0 no \u00a0 comporta \u00a0imputaci\u00f3n \u00a0alguna, \u00a0a \u00a0lo sumo es el anuncio de la \u00a0consecuencia \u00a0 patrimonial \u00a0 que \u00a0la \u00a0declaratoria \u00a0de \u00a0responsabilidad \u00a0acarrea \u00a0respecto \u00a0 \u00a0de \u00a0 los \u00a0 bienes \u00a0 involucrados \u00a0 en \u00a0 los \u00a0 delitos \u00a0 de \u00a0 cuya \u00a0 comisi\u00f3n \u00a0 se \u00a0acusa \u00a0al \u00a0requerido, \u00a0tema ajeno a \u00a0la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n, \u00a0raz\u00f3n por la cual no se encuentra comprendido \u00a0dentro \u00a0de \u00a0los \u00a0aspectos \u00a0que \u00a0deba \u00a0ocuparse el concepto a emitir por la Sala. \u00a0\u00a0<\/p>\n<p>5. \u00a0 Equivalencia \u00a0 de \u00a0la \u00a0providencia \u00a0proferida en el extranjero \u00a0\u00a0<\/p>\n<p>Esta exigencia que corresponde examinar a \u00a0la \u00a0Corporaci\u00f3n, \u00a0se\u00f1alada \u00a0en el numeral 2\u00b0 del art\u00edculo 493 del C\u00f3digo de \u00a0Procedimiento \u00a0Penal, \u00a0Ley \u00a0906 \u00a0de \u00a02004, \u00a0se \u00a0orienta \u00a0a verificar si la pieza \u00a0procesal \u00a0ofrecida \u00a0por \u00a0el \u00a0pa\u00eds \u00a0requirente \u00a0es \u00a0equivalente \u00a0a la acusaci\u00f3n \u00a0prevista en el ordenamiento procesal interno. \u00a0\u00a0<\/p>\n<p>Conviene \u00a0recordar \u00a0que \u00a0no \u00a0se \u00a0trata de \u00a0establecer \u00a0identidad \u00a0entre \u00a0ambas actuaciones, pues lo relevante es determinar \u00a0si \u00a0la \u00a0decisi\u00f3n \u00a0entregada \u00a0da \u00a0paso \u00a0al juicio, adem\u00e1s, se debe constatar si \u00a0brinda \u00a0un \u00a0relato \u00a0sucinto \u00a0del comportamiento imputado, con especificaci\u00f3n de \u00a0las \u00a0circunstancias \u00a0de \u00a0lugar y tiempo e, igualmente si expresa con claridad la \u00a0calificaci\u00f3n jur\u00eddica se\u00f1alando los preceptos aplicables. \u00a0\u00a0<\/p>\n<p>Tal \u00a0exigencia \u00a0se \u00a0cumple \u00a0frente \u00a0a \u00a0la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n \u00a0de MIGUEL ANTONIO MONROY \u00a0RAM\u00cdREZ, \u00a0presentada por el Gobierno de los Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica, \u00a0toda \u00a0vez \u00a0que la Acusaci\u00f3n \u00a0Formal \u00a0de \u00a0Reemplazo No. 10-20798-CR-COOKE(s) dictada \u00a0el \u00a07 \u00a0de \u00a0junio \u00a0de \u00a02011 \u00a0en \u00a0la Corte Distrital de los Estados Unidos para el \u00a0Distrito \u00a0Sur \u00a0de \u00a0Florida \u00a0al \u00a0igual \u00a0que \u00a0ocurre \u00a0con el documento de la misma \u00a0\u00edndole \u00a0en \u00a0el ordenamiento colombiano, marcan el comienzo del juicio, etapa en \u00a0la \u00a0cual \u00a0el \u00a0procesado \u00a0tiene \u00a0la oportunidad de controvertir las pruebas y los \u00a0cargos a \u00e9l atribuidos. \u00a0\u00a0<\/p>\n<p>De \u00a0 la \u00a0 misma \u00a0 forma, \u00a0 el \u00a0requerimiento \u00a0de las autoridades for\u00e1neas contiene \u00a0la \u00a0informaci\u00f3n relativa a lugares \u00a0y \u00a0\u00e9pocas \u00a0de \u00a0ocurrencia de los hechos, \u00a0 circunstancias \u00a0 bajo \u00a0las \u00a0cuales \u00a0actuaba MONROY RAM\u00cdREZ y \u00a0las disposiciones violadas con los actos all\u00ed definidos. \u00a0\u00a0<\/p>\n<p>Por tanto, es indiscutible la equivalencia \u00a0existente \u00a0entre \u00a0la acusaci\u00f3n dictada en el extranjero y la\u00a0 se\u00f1alada en \u00a0los art\u00edculos 336 y 337 de la Ley 906 de 2004. \u00a0\u00a0<\/p>\n<p>6. En relaci\u00f3n \u00a0con \u00a0las \u00a0exigencias \u00a0constitucionales para negar la extradici\u00f3n de nacionales, \u00a0la \u00a0Sala \u00a0no \u00a0observa \u00a0su \u00a0presencia \u00a0toda vez en el caso analizado, los delitos \u00a0imputados \u00a0a \u00a0MIGUEL \u00a0ANTONIO \u00a0MONROY \u00a0RAM\u00cdREZ \u00a0son \u00a0de \u00a0naturaleza \u00a0com\u00fan, no \u00a0pol\u00edtica, \u00a0 ocurridos \u00a0 despu\u00e9s \u00a0 de \u00a0 1997 \u00a0 en \u00a0territorio \u00a0de \u00a0los \u00a0Estados \u00a0Unidos. \u00a0\u00a0<\/p>\n<p>\u00a0 7. Conclusiones \u00a0\u00a0<\/p>\n<p>Los \u00a0anteriores \u00a0razonamientos \u00a0permiten \u00a0establecer \u00a0a \u00a0la \u00a0Sala, \u00a0que \u00a0de \u00a0acuerdo \u00a0con lo manifestado por el Ministerio \u00a0P\u00fablico \u00a0y \u00a0la \u00a0Defensa, est\u00e1n dadas las exigencias legales para conceptuar de \u00a0manera \u00a0favorable \u00a0a la solicitud de extradici\u00f3n formalizada por el Gobierno de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica \u00a0a \u00a0trav\u00e9s \u00a0de su Embajada en nuestro pa\u00eds, \u00a0respecto \u00a0del \u00a0ciudadano \u00a0colombiano \u00a0MIGUEL ANTONIO \u00a0MONROY \u00a0RAM\u00cdREZ, por los \u00a0cargos \u00a0 \u00a0 atribuidos \u00a0 \u00a0 en \u00a0 \u00a0la \u00a0 \u00a0Acusaci\u00f3n \u00a0Formal \u00a0de \u00a0Reemplazo No. 10-20798-CR-COOKE(s) dictada \u00a0el \u00a07 \u00a0de \u00a0junio \u00a0de \u00a02011 \u00a0en \u00a0la Corte Distrital de los Estados Unidos para el \u00a0Distrito \u00a0 \u00a0 \u00a0 \u00a0Sur \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0Florida6. \u00a0\u00a0<\/p>\n<p>Por \u00a0 \u00a0 \u00a0tanto, \u00a0 \u00a0 \u00a0y \u00a0en \u00a0orden \u00a0a \u00a0proteger los derechos \u00a0fundamentales \u00a0 \u00a0del \u00a0 \u00a0requerido, \u00a0 \u00a0el \u00a0Estado \u00a0solicitante \u00a0deber\u00e1 \u00a0garantizarle la permanencia en el \u00a0pa\u00eds \u00a0extranjero y el retorno al de origen en condiciones de dignidad y respeto \u00a0por \u00a0la \u00a0persona \u00a0humana \u00a0cuando \u00a0el \u00a0extraditado \u00a0llegare \u00a0a \u00a0ser \u00a0sobrese\u00eddo, \u00a0absuelto, \u00a0declarado \u00a0no \u00a0culpable \u00a0o \u00a0eventos similares, incluso despu\u00e9s de su \u00a0liberaci\u00f3n \u00a0por \u00a0haber \u00a0cumplido la pena impuesta, en raz\u00f3n de la extradici\u00f3n \u00a0concedida. \u00a0\u00a0<\/p>\n<p>Del mismo modo, atendiendo lo dispuesto en \u00a0el \u00a0art\u00edculo \u00a0494 de la Ley 906 de 2004, se advertir\u00e1 que el Gobierno Nacional \u00a0puede \u00a0subordinar \u00a0la concesi\u00f3n de la extradici\u00f3n a exigencias tales como: que \u00a0el \u00a0solicitado \u00a0no \u00a0sea \u00a0juzgado \u00a0por \u00a0hechos \u00a0anteriores \u00a0diversos \u00a0de \u00a0los que \u00a0motivaron \u00a0la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n; ni sometido a sanciones distintas de \u00a0las \u00a0impuestas en la eventual condena; ni a penas de muerte, destierro, prisi\u00f3n \u00a0perpetua \u00a0o \u00a0confiscaci\u00f3n, \u00a0desaparici\u00f3n \u00a0forzada, \u00a0torturas, \u00a0tratos crueles, \u00a0inhumanos \u00a0o \u00a0degradantes, \u00a0por \u00a0el \u00a0pa\u00eds \u00a0solicitante, \u00a0de \u00a0conformidad con lo \u00a0dispuesto \u00a0por los art\u00edculos 12 y 34 de la Constituci\u00f3n Pol\u00edtica de Colombia; \u00a0y \u00a0como \u00a0lo \u00a0sugiere \u00a0la \u00a0Procuradur\u00eda \u00a0General \u00a0de \u00a0la Naci\u00f3n a trav\u00e9s de su \u00a0Delegado. \u00a0\u00a0<\/p>\n<p>As\u00ed mismo, debe condicionar la entrega de \u00a0MIGUEL \u00a0 ANTONIO \u00a0 MONROY \u00a0 RAM\u00cdREZ \u00a0 al \u00a0respeto \u00a0por \u00a0todas \u00a0las garant\u00edas debidas a su condici\u00f3n de \u00a0justiciable, \u00a0en \u00a0particular: \u00a0tener acceso a un proceso p\u00fablico sin dilaciones \u00a0injustificadas; \u00a0se \u00a0presuma \u00a0su \u00a0inocencia; \u00a0cuente \u00a0con \u00a0un \u00a0int\u00e9rprete \u00a0y un \u00a0defensor \u00a0designado \u00a0por \u00a0\u00e9l \u00a0o \u00a0por \u00a0el \u00a0Estado; se le conceda tiempo y medios \u00a0adecuados \u00a0para preparar la defensa, presentar pruebas y controvertir las que se \u00a0aduzcan \u00a0en \u00a0contra; \u00a0a \u00a0que \u00a0su \u00a0situaci\u00f3n \u00a0de \u00a0privaci\u00f3n \u00a0de \u00a0la libertad se \u00a0desarrolle \u00a0en \u00a0condiciones \u00a0dignas; a que la eventual pena que se le imponga no \u00a0trascienda \u00a0de su persona; a que la sentencia pueda ser apelada ante un tribunal \u00a0superior \u00a0y \u00a0la \u00a0pena \u00a0privativa \u00a0de \u00a0la libertad tenga la finalidad esencial de \u00a0reforma \u00a0y readaptaci\u00f3n social (Art\u00edculos 29 de la Constituci\u00f3n; 9 y 10 de la \u00a0Declaraci\u00f3n \u00a0 Universal \u00a0 de \u00a0 los \u00a0 Derechos \u00a0 Humanos; \u00a05-3.6, \u00a07-2.5, \u00a08-1.2 \u00a0(a) \u00a0 (b) \u00a0 \u00a0(c) \u00a0(d) \u00a0 \u00a0(e) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(f) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(g) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(h).3.4.5, \u00a09 \u00a0de \u00a0la \u00a0Convenci\u00f3n \u00a0Americana de Derechos Humanos; \u00a09-2.3, \u00a010-1.2.3, 14-1.2.3,5, y 15 del Pacto Internacional de Derechos Civiles y \u00a0Pol\u00edticos). \u00a0\u00a0<\/p>\n<p>Igualmente, \u00a0el Gobierno debe condicionar \u00a0la \u00a0entrega \u00a0del requerido a que el pa\u00eds solicitante, conforme a sus pol\u00edticas \u00a0internas \u00a0sobre \u00a0la \u00a0materia, \u00a0le \u00a0ofrezca \u00a0posibilidades racionales y reales de \u00a0contacto \u00a0 regular \u00a0 con \u00a0 sus \u00a0familiares \u00a0m\u00e1s \u00a0cercanos, \u00a0habida \u00a0cuenta, \u00a0la \u00a0Constituci\u00f3n \u00a0de \u00a01991, \u00a0en su art\u00edculo 42, reconoce a la familia como n\u00facleo \u00a0esencial \u00a0de \u00a0la sociedad y garantiza su protecci\u00f3n, \u00a0amparo \u00a0 tambi\u00e9n \u00a0 otorgado \u00a0 por \u00a0la \u00a0Convenci\u00f3n \u00a0Americana \u00a0sobre \u00a0Derechos \u00a0Humanos \u00a0(art\u00edculo \u00a017) y el Pacto Internacional de \u00a0Derechos Civiles y Pol\u00edticos (art\u00edculo 23). \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, la Sala se\u00f1ala, en virtud de lo \u00a0dispuesto \u00a0por \u00a0el \u00a0numeral 2\u00ba del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, \u00a0que \u00a0 \u00a0 \u00a0 corresponde \u00a0 \u00a0 \u00a0al \u00a0 \u00a0 \u00a0Presidente \u00a0de la Rep\u00fablica como supremo director de la pol\u00edtica \u00a0exterior \u00a0 y \u00a0 de \u00a0las \u00a0relaciones \u00a0internacionales, \u00a0realizar \u00a0el \u00a0seguimiento \u00a0a \u00a0los \u00a0condicionamientos \u00a0impuestos \u00a0en \u00a0la \u00a0concesi\u00f3n \u00a0de la extradici\u00f3n y determinar las consecuencias \u00a0que se derivar\u00edan de su eventual incumplimiento. \u00a0\u00a0<\/p>\n<p>Cabe \u00a0 \u00a0subrayar \u00a0 que \u00a0 MIGUEL \u00a0ANTONIO \u00a0MONROY \u00a0RAM\u00cdREZ\u00a0 \u00a0se \u00a0 encuentra \u00a0privado \u00a0de \u00a0la \u00a0libertad \u00a0para \u00a0los \u00a0efectos \u00a0del \u00a0tr\u00e1mite \u00a0de \u00a0extradici\u00f3n, \u00a0 desde \u00a0 el \u00a0 primero \u00a0(1) \u00a0de \u00a0septiembre \u00a0de \u00a0dos \u00a0mil \u00a0once \u00a0(2011), \u00a0lapso que deber\u00e1 \u00a0tenerse \u00a0como \u00a0parte \u00a0de \u00a0la \u00a0pena \u00a0que \u00a0llegare \u00a0a \u00a0imponerse en el pa\u00eds requirente. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0expuesto, \u00a0la \u00a0Sala de Casaci\u00f3n \u00a0Penal \u00a0de \u00a0la \u00a0Corte \u00a0Suprema de Justicia, CONCEPT\u00daA \u00a0FAVORABLEMENTE \u00a0a \u00a0la \u00a0extradici\u00f3n \u00a0de MIGUEL \u00a0 ANTONIO \u00a0 MONROY \u00a0 RAM\u00cdREZ, \u00a0de \u00a0anotaciones \u00a0conocidas en el curso del tr\u00e1mite, \u00a0por \u00a0los cargos atribuidos en la Acusaci\u00f3n Formal de \u00a0Reemplazo \u00a0No. \u00a010-20798-CR-COOKE(s) \u00a0dictada \u00a0el 7 de junio de 2011 en la Corte \u00a0Distrital \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0para el Distrito Sur de Florida7. \u00a0\u00a0<\/p>\n<p>Comun\u00edquese \u00a0 \u00a0esta \u00a0 determinaci\u00f3n \u00a0al \u00a0requerido \u00a0MIGUEL \u00a0ANTONIO \u00a0 MONROY \u00a0 RAM\u00cdREZ, \u00a0 a \u00a0su \u00a0defensor, \u00a0al \u00a0Ministerio \u00a0P\u00fablico \u00a0y \u00a0al \u00a0Fiscal \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0para lo de\u00a0 \u00a0su\u00a0 cargo. \u00a0\u00a0<\/p>\n<p>Devu\u00e9lvase el \u00a0expediente \u00a0 al \u00a0 Ministerio \u00a0 del \u00a0 Interior \u00a0y \u00a0de \u00a0Justicia \u00a0para \u00a0lo \u00a0de \u00a0su \u00a0competencia. \u00a0\u00a0<\/p>\n<p>JOS\u00c9 \u00a0 LEONIDAS \u00a0 BUSTOS \u00a0 MART\u00cdNEZ \u00a0\u00a0<\/p>\n<p>JOS\u00c9 \u00a0 \u00a0 \u00a0LUIS \u00a0 \u00a0 BARCEL\u00d3 \u00a0CAMACHO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0FERNANDO ALBERTO CASTRO CABALLERO \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Comisi\u00f3n de servicio \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 \u00a0<\/p>\n<p>SIGIFREDO \u00a0ESPINOSA \u00a0 \u00a0 P\u00c9REZ \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0MARIA \u00a0 DEL \u00a0 ROSARIO \u00a0 GONZ\u00c1LEZ \u00a0MU\u00d1\u00d3Z\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Permiso \u00a0<\/p>\n<p>AUGUSTO \u00a0J. \u00a0IB\u00c1\u00d1EZ \u00a0 \u00a0 GUZM\u00c1N \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 LUIS GUILLERMO SALAZAR OTERO \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JULIO \u00a0 \u00a0 \u00a0 ENRIQUE \u00a0 \u00a0 \u00a0 SOCHA \u00a0SALAMANCA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JAVIER ZAPATA ORTIZ \u00a0\u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p>1 Folio \u00a0219 cuaderno anexo. \u00a0\u00a0<\/p>\n<p>2 Folio \u00a0219 cuaderno anexo. \u00a0\u00a0<\/p>\n<p>3 En \u00a0el \u00a0presente \u00a0caso \u00a0se \u00a0aplica \u00a0la \u00a0Ley \u00a0906 \u00a0de \u00a02004 por cuanto los hechos que \u00a0sustentan \u00a0la petici\u00f3n de extradici\u00f3n ocurrieron despu\u00e9s del primero de enero \u00a0de \u00a02005, \u00a0fecha en la cual entr\u00f3 en vigencia el nuevo C\u00f3digo de Procedimiento \u00a0Penal. \u00a0En \u00a0este \u00a0sentido, \u00a0ver \u00a0autos \u00a0del \u00a04 \u00a0de abril y 3 de octubre de 2006, \u00a0radicados 24187 y 25080, respectivamente, entre otros.\u00a0 \u00a0\u00a0<\/p>\n<p>4 \u00a0Folio 219 cuaderno anexo. \u00a0\u00a0<\/p>\n<p>5 \u00a0Conceptos \u00a0del \u00a03 \u00a0de \u00a0mayo de 2007 y 16 de diciembre de 2008, radicados 26756 y \u00a030626, respectivamente. \u00a0\u00a0<\/p>\n<p>6 \u00a0Folio 219 cuaderno anexo. \u00a0\u00a0<\/p>\n<p>7 \u00a0Folio 219 cuaderno anexo. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso n\u00ba 37826 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CORTE SUPREMA DE JUSTICIA \u00a0\u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente: \u00a0 JAVIER ZAPATA ORTIZ \u00a0 Aprobado \u00a0 \u00a0Acta \u00a0 \u00a0No. \u00a0 \u00a0121 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Bogot\u00e1 \u00a0D. C., once (11) de abril de dos \u00a0mil doce (2012) \u00a0\u00a0 VISTOS: \u00a0\u00a0 Surtido \u00a0 el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-24145","post","type-post","status-publish","format-standard","hentry","category-20"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/24145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=24145"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/24145\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=24145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=24145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=24145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}