{"id":23482,"date":"2023-09-12T17:19:55","date_gmt":"2023-09-12T17:19:55","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3348602-05-12\/"},"modified":"2023-09-12T17:19:55","modified_gmt":"2023-09-12T17:19:55","slug":"3348602-05-12","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3348602-05-12\/","title":{"rendered":"33486(02-05-12)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso n\u00ba 33486 \u00a0<\/p>\n<p>CORTE SUPRE MA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>FERNANDO \u00a0ALBERTO \u00a0CASTRO \u00a0CABALLERO \u00a0\u00a0<\/p>\n<p>Aprobado \u00a0 \u00a0Acta \u00a0N\u00b0155 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D. \u00a0C., dos (2) de mayo de dos mil \u00a0dos doce (2012). \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Procede \u00a0la \u00a0Sala \u00a0a \u00a0emitir \u00a0el \u00a0fallo \u00a0de \u00a0casaci\u00f3n \u00a0dentro \u00a0del \u00a0proceso \u00a0adelantado por la Justicia Penal Militar contra \u00a0Luis \u00a0Alberto \u00a0Padilla \u00a0Zamboni, \u00a0luego \u00a0de \u00a0admitida \u00a0la \u00a0demanda \u00a0de casaci\u00f3n \u00a0presentada \u00a0por \u00a0su \u00a0defensor \u00a0y \u00a0una \u00a0vez \u00a0rendido \u00a0el concepto de rigor por el \u00a0Procurador Delegado en lo Penal. \u00a0\u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>Fueron resumidos por el juzgador de instancia \u00a0as\u00ed: \u00a0\u00a0<\/p>\n<p>\u201cSucedieron \u00a0en \u00a0la localidad de Barbacoas \u00a0Nari\u00f1o, \u00a0en \u00a0horas \u00a0de la noche del 15 de diciembre del a\u00f1o 2003, cuando hasta \u00a0el \u00a0negocio \u00a0de \u00a0billares \u00a0\u201cAmorama\u201d \u00a0que atend\u00eda la se\u00f1ora Claudia Lorena \u00a0Franco \u00a0Garc\u00eda, llegaron los policiales Padilla y Garz\u00f3n, quienes cumpl\u00edan el \u00a0cuarto \u00a0turno \u00a0de \u00a0servicio, \u00a0con \u00a0el \u00a0prop\u00f3sito de practicar una requisa y del \u00a0bolso \u00a0de \u00a0la \u00a0prenombrada, \u00a0sacaron \u00a0la suma de diez millones de pesos, la cual \u00a0hab\u00eda \u00a0sido \u00a0dada \u00a0a guardar por el particular Gabriel P\u00e9rez, manifestando los \u00a0agentes \u00a0que era el producto del narcotr\u00e1fico. Las dos personas fueron llevadas \u00a0a \u00a0las \u00a0dependencias \u00a0policiales \u00a0donde \u00a0fueron \u00a0privadas \u00a0de su libertad y bajo \u00a0amenazas \u00a0de colocarlos a disposici\u00f3n de la Fiscal\u00eda, les exigieron el pago de \u00a0una \u00a0suma \u00a0de \u00a0dinero \u00a0a cambio de su libertad, misma que se concret\u00f3 en cuatro \u00a0millones de pesos con la que \u00e9sta se hizo efectiva\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0ACTUACI\u00d3N \u00a0PROCESAL \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>1. \u00a0 Luego \u00a0 de \u00a0 que \u00a0 los \u00a0hechos \u00a0fueron \u00a0denunciados \u00a0por \u00a0Claudia \u00a0\u00a0<\/p>\n<p>Lorena Franco Garc\u00eda, la Fiscal\u00eda 158 Penal \u00a0Militar \u00a0de \u00a0Pasto,\u00a0 \u00a0el 2 de octubre de 2007 acus\u00f3 a Luis Alberto Padilla \u00a0Zamboni \u00a0y \u00a0a \u00a0\u00c1lvaro Andr\u00e9s Garz\u00f3n Olaya de los delitos de privaci\u00f3n ilegal \u00a0de \u00a0la \u00a0libertad, abandono de puesto y concusi\u00f3n. Por los delitos de privaci\u00f3n \u00a0ilegal \u00a0de \u00a0la libertad y concusi\u00f3n se dispuso la ruptura de la unidad procesal \u00a0en \u00a0aras \u00a0de que la investigaci\u00f3n fuera asumida por la jurisdicci\u00f3n ordinaria. \u00a0Contra \u00a0la \u00a0anterior decisi\u00f3n la defensa de los procesados interpuso el recurso \u00a0de \u00a0apelaci\u00f3n, \u00a0el \u00a0cual \u00a0fue \u00a0resuelto \u00a0por \u00a0la \u00a0Fiscal\u00eda 5\u00aa Delgada ante el \u00a0Tribunal \u00a0Superior Militar el 7 de febrero de 2008, confirmando en su integridad \u00a0el \u00a0calificatorio \u00a0de primera instancia en lo referente al delito de abandono de \u00a0puesto, \u00a0 pues \u00a0en \u00a0relaci\u00f3n \u00a0con \u00a0los \u00a0otros \u00a0comportamientos \u00a0la \u00a0competencia \u00a0correspond\u00eda a la jurisdicci\u00f3n ordinaria. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02. \u00a0En lo referente al delito de abandono del puesto, el Juzgado 155 \u00a0Penal \u00a0Militar, \u00a0el 7 de abril de 2008, emiti\u00f3 sentencia absolutoria a favor de \u00a0ambos \u00a0procesados, \u00a0la \u00a0cual \u00a0fue \u00a0impugnada por el delegado de la Procuradur\u00eda \u00a0General de la Naci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a03. \u00a0El \u00a0Tribunal \u00a0Superior \u00a0Militar en decisi\u00f3n del 31 de agosto de \u00a02009, \u00a0revoc\u00f3 \u00a0la \u00a0absoluci\u00f3n \u00a0y \u00a0en su lugar, conden\u00f3 a Luis Alberto Padilla \u00a0Zamboni \u00a0y \u00a0a \u00a0\u00c1lvaro \u00a0Andr\u00e9s Garz\u00f3n como responsables del delito de abandono \u00a0del \u00a0 puesto, \u00a0 motivo \u00a0 por \u00a0 el \u00a0cual \u00a0les \u00a0impuso \u00a0la \u00a0pena \u00a0de \u00a0un \u00a0a\u00f1o \u00a0de \u00a0arresto. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a04. \u00a0Contra \u00a0esta \u00a0decisi\u00f3n \u00a0el \u00a0defensor \u00a0de \u00a0Luis \u00a0Alberto Padilla \u00a0Zamboni \u00a0interpuso \u00a0el recurso extraordinario de casaci\u00f3n, el cual fue admitido \u00a0por la Sala en auto del 1\u00ba de junio de 2011. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a05. \u00a0El \u00a0Procurador \u00a0Delegado \u00a0en \u00a0lo \u00a0penal, \u00a0rindi\u00f3 su concepto el \u00a0pasado \u00a016 \u00a0de \u00a0diciembre, \u00a0motivo \u00a0por \u00a0el cual la Corte proceder\u00e1 a emitir el \u00a0fallo de rigor. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>1. El censor plantea la casaci\u00f3n por la v\u00eda \u00a0excepcional \u00a0al \u00a0considerar \u00a0trasgredido \u00a0el \u00a0debido proceso de su representado, \u00a0ante \u00a0el desconocimiento del principio de presunci\u00f3n de inocencia y de in dubio \u00a0pro reo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Luego de hacer una serie de citas normativas sobre el \u00a0 \u00a0\u00a0<\/p>\n<p>lugar \u00a0que \u00a0ocupa \u00a0en \u00a0el \u00a0orden \u00a0interno \u00a0e \u00a0internacional \u00a0el \u00a0principio \u00a0del indubio pro reo, se\u00f1ala que la duda emerge al \u00a0concluir \u00a0el \u00a0Tribunal \u00a0que \u00a0el \u00a0acusado \u00a0junto \u00a0con \u00a0su \u00a0compa\u00f1ero de trabajo, \u00a0abandonaron \u00a0su \u00a0puesto \u00a0sin contar con la autorizaci\u00f3n de sus superiores, para \u00a0luego \u00a0indicar \u00a0el \u00a0ad \u00a0quem \u00a0que \u00a0s\u00ed \u00a0contaron con dicho permiso, afirmaciones \u00a0contradictorias que ponen en evidencia el estado de duda. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02. \u00a0Como \u00a0cargo de la demanda, acusa al Tribunal Superior Militar de \u00a0incurrir \u00a0en \u00a0una \u00a0violaci\u00f3n \u00a0indirecta de la ley sustancial por error de hecho \u00a0por \u00a0falso \u00a0juicio \u00a0de \u00a0identidad \u00a0derivado \u00a0de \u00a0la incorrecta valoraci\u00f3n de lo \u00a0manifestado \u00a0por Luis Alberto Padilla Zamboni en indagatoria y el testimonio del \u00a0T.C \u00a0Guzm\u00e1n; \u00a0de \u00a0igual forma denuncia al fallo de contener un falso raciocinio \u00a0por \u00a0la existencia de inferencias que van en contrav\u00eda de las reglas de la sana \u00a0cr\u00edtica, \u00a0de \u00a0la \u00a0l\u00f3gica \u00a0y \u00a0de \u00a0la \u00a0experiencia, \u00a0lo que llev\u00f3 al Tribunal a \u00a0otorgarle \u00a0a \u00a0un \u00a0medio \u00a0de \u00a0prueba \u00a0un \u00a0m\u00e9rito \u00a0persuasivo \u00a0distinto al que en \u00a0realidad correspond\u00eda. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02.1 \u00a0Frente al falso juicio de identidad respecto del testimonio del \u00a0T.C \u00a0Esteban \u00a0Guzm\u00e1n \u00a0Vargas, \u00a0indica \u00a0el \u00a0censor \u00a0que \u00a0el \u00a0juzgador de segunda \u00a0instancia \u00a0tergivers\u00f3 su contenido, dado que claramente el testigo inform\u00f3 que \u00a0uno \u00a0de los policiales, \u00c1lvaro Andr\u00e9s Garz\u00f3n, le pidi\u00f3 autorizaci\u00f3n para ir \u00a0a \u00a0verificar \u00a0una persona sospechosa a unos billares y que \u00e9l lo autoriz\u00f3 para \u00a0que \u00a0se \u00a0desplazara \u00a0al \u00a0lugar en compa\u00f1\u00eda de otro agente que se encontraba al \u00a0servicio de la Alcald\u00eda, siendo \u00e9ste el patrullero Padilla. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0tergiversaci\u00f3n \u00a0en \u00a0la mentada prueba la centra el libelista en \u00a0que \u00a0el \u00a0Tribunal \u00a0no \u00a0se \u00a0percat\u00f3 \u00a0que \u00a0el testigo en las dos declaraciones se \u00a0refer\u00eda \u00a0a \u00a0dos \u00a0situaciones \u00a0distintas, \u00a0en \u00a0la primera el TC. Garz\u00f3n aludi\u00f3 \u00a0expresamente \u00a0 a \u00a0que \u00a0no \u00a0se \u00a0hab\u00eda \u00a0cumplido \u00a0un \u00a0procedimiento \u00a0judicial \u00a0de \u00a0allanamiento \u00a0y registro, mientras que en la segunda, se refiri\u00f3 expresamente a \u00a0que \u00a0s\u00ed \u00a0se \u00a0hab\u00eda realizado un procedimiento policivo de pesquisa o requisa a \u00a0unos \u00a0sospechosos \u00a0que \u00a0son procedimientos distintos, lo cual descarta cualquier \u00a0contradicci\u00f3n \u00a0 en \u00a0el \u00a0testimonio \u00a0de \u00a0T.C \u00a0Esteban \u00a0Guzm\u00e1n \u00a0Vargas \u00a0del \u00a0que \u00a0claramente \u00a0se concluye, s\u00ed autoriz\u00f3 el desplazamiento de los policiales hacia \u00a0el \u00a0billar \u00a0\u201cAmorama\u201d \u00a0encaminado \u00a0a \u00a0requisar \u00a0a unos sospechosos, de donde \u00a0devendr\u00eda clara la inocencia de ambos acusados. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02.2 \u00a0Al \u00a0abordar lo respectivo al falso juicio de identidad frente a \u00a0la \u00a0indagatoria \u00a0de \u00a0Luis \u00a0Alberto \u00a0Padilla \u00a0Zamboni, sostiene el demandante que \u00a0\u00e9ste \u00a0manifest\u00f3 \u00a0que \u00a0acompa\u00f1\u00f3 \u00a0al \u00a0agente \u00a0Garz\u00f3n \u00a0al billar \u201cAmorama\u201d \u00a0porque \u00a0le \u00a0dijo \u00a0que \u00a0estaba \u00a0autorizado por el capit\u00e1n Guzm\u00e1n para hacer ese \u00a0procedimiento, \u00a0no \u00a0obstante \u00a0el \u00a0Tribunal se\u00f1al\u00f3 que Padilla Zamboni se fue a \u00a0acompa\u00f1ar \u00a0al \u00a0agente Garz\u00f3n sin que hubiese manifestado o se demuestre que el \u00a0procedimiento \u00a0obedeci\u00f3 \u00a0a \u00a0una \u00a0orden \u00a0u \u00a0operativo \u00a0dispuesto por el Capit\u00e1n \u00a0Guzm\u00e1n \u00a0de donde deviene el cercenamiento de lo manifestado por el procesado en \u00a0su indagatoria. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02.3 \u00a0Por \u00a0\u00faltimo, \u00a0en \u00a0lo \u00a0atinente \u00a0al \u00a0falso raciocinio, \u00e9ste se \u00a0remonta \u00a0al \u00a0testimonio \u00a0de Esteban Guzm\u00e1n Vargas en donde se desconocieron los \u00a0principios \u00a0 de \u00a0 la \u00a0l\u00f3gica \u00a0jur\u00eddica \u00a0tales \u00a0como \u00a0el \u00a0principio \u00a0de \u00a0raz\u00f3n \u00a0suficiente, \u00a0seg\u00fan \u00a0el \u00a0cual \u00a0s\u00f3lo \u00a0es \u00a0verdadero \u00a0aquello que se puede probar \u00a0suficientemente, \u00a0bas\u00e1ndose en otros conocimientos o razones ya demostradas y\/o \u00a0aquellas reglas del silogismo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a0falso \u00a0raciocinio lo ajusta el censor a la falta de credibilidad \u00a0que \u00a0le \u00a0mereci\u00f3 \u00a0al \u00a0Tribunal este testimonio, al haber declarado inicialmente \u00a0que \u00a0no \u00a0hab\u00eda \u00a0realizado \u00a0un \u00a0procedimiento \u00a0judicial \u00a0y \u00a0posteriormente haber \u00a0afirmado \u00a0que \u00a0s\u00ed \u00a0hab\u00eda \u00a0ordenado \u00a0una intervenci\u00f3n policiva, sin que exista \u00a0sustento \u00a0probatorio \u00a0para \u00a0fundamentar debidamente esa inferencia, esto es, que \u00a0el \u00a0 dicho \u00a0del \u00a0declarante \u00a0no \u00a0es \u00a0digno \u00a0de \u00a0credibilidad \u00a0por \u00a0una \u00a0supuesta \u00a0contradicci\u00f3n en la que incurri\u00f3 el testigo. \u00a0\u00a0<\/p>\n<p>3. \u00a0Para \u00a0el libelista son trascendentes los \u00a0errores \u00a0en \u00a0los \u00a0que incurri\u00f3 el Tribunal, toda vez que las pruebas que fueron \u00a0incorrectamente \u00a0valoradas, \u00a0constituyeron \u00a0el soporte de la condena, cuando del \u00a0contenido \u00a0del \u00a0testimonio \u00a0de \u00a0Esteban \u00a0Guzm\u00e1n \u00a0Vargas y de la indagatoria del \u00a0procesado, \u00a0s\u00f3lo pod\u00eda concluirse que el d\u00eda de los hechos, \u00e9ste s\u00ed contaba \u00a0con \u00a0la \u00a0autorizaci\u00f3n \u00a0de \u00a0su \u00a0superior \u00a0para \u00a0ausentarse del lugar de trabajo. \u00a0\u00a0<\/p>\n<p>concepto de la procuraduria \u00a0<\/p>\n<p>delegadA \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01. \u00a0El \u00a0delegado \u00a0de \u00a0la \u00a0Procuradur\u00eda \u00a0frente \u00a0al \u00a0cargo \u00a0primero, \u00a0denominado \u00a0falso \u00a0juicio \u00a0de identidad se\u00f1ala que el Tribunal Superior Militar \u00a0fue \u00a0fiel \u00a0al \u00a0contenido \u00a0del \u00a0testimonio de Esteban Guzm\u00e1n Vargas, d\u00e1ndole el \u00a0alcance correcto de acuerdo con las reglas de la sana cr\u00edtica. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Resalta \u00a0el \u00a0oficio \u00a0firmado \u00a0por este testigo el 17 de diciembre de \u00a02003, \u00a0 dirigido \u00a0 a \u00a0 la \u00a0Fiscal\u00eda \u00a046 \u00a0Seccional \u00a0de \u00a0Barbacoas \u00a0\u2013Nari\u00f1o, \u00a0 en \u00a0el \u00a0que \u00a0con \u00a0claridad \u00a0informa \u00a0que para el 15 de diciembre de 2003, no tuvo ning\u00fan conocimiento sobre \u00a0un \u00a0procedimiento \u00a0de \u00a0allanamiento \u00a0y \u00a0registro \u00a0al establecimiento p\u00fablico de \u00a0raz\u00f3n \u00a0social \u00a0\u201cAmorama\u201d, \u00a0administrado \u00a0por Claudia Lorena Franco Garc\u00eda, \u00a0adem\u00e1s \u00a0de \u00a0que \u00a0no \u00a0orden\u00f3 \u00a0al \u00a0personal \u00a0a \u00a0su cargo que participaran en una \u00a0diligencia de ese tipo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0esa \u00a0medida \u00a0no \u00a0pueden resultar cre\u00edbles las explicaciones que \u00a0rindi\u00f3 \u00a0cuatro \u00a0a\u00f1os \u00a0despu\u00e9s el declarante, cuando indic\u00f3 que en ese oficio \u00a0no \u00a0hizo \u00a0alusi\u00f3n \u00a0a \u00a0la \u00a0participaci\u00f3n \u00a0de \u00a0miembros \u00a0de la Polic\u00eda Nacional \u00a0adscritos \u00a0a \u00a0la estaci\u00f3n que comandada debido a que la Fiscal\u00eda General de la \u00a0Naci\u00f3n\u00a0 no lo interrog\u00f3 al respecto. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Agrega \u00a0que \u00a0el \u00a0Capit\u00e1n \u00a0Guzm\u00e1n \u00a0estaba \u00a0en \u00a0el \u00a0deber \u00a0de dar la \u00a0informaci\u00f3n \u00a0completa \u00a0y \u00a0detallada \u00a0y \u00a0sobre \u00a0todo clarificar que Luis Alberto \u00a0Padilla \u00a0 Zamboni \u00a0 y \u00a0 \u00c1lvaro \u00a0 Andr\u00e9s \u00a0Garz\u00f3n \u00a0Olaya \u00a0no \u00a0pod\u00edan \u00a0realizar \u00a0procedimientos \u00a0 de \u00a0 allanamiento \u00a0y \u00a0registro, \u00a0pues \u00a0esas \u00a0diligencias \u00a0s\u00f3lo \u00a0corresponde \u00a0hacerlas \u00a0efectivas \u00a0bajo \u00a0la \u00a0responsabilidad \u00a0de \u00a0las autoridades \u00a0judiciales \u00a0en \u00a0cumplimiento de una orden de la misma naturaleza, igualmente que \u00a0esos \u00a0policiales \u00a0estaban en el establecimiento abierto al p\u00fablico, confirmando \u00a0una \u00a0informaci\u00f3n \u00a0sobre el porte de una arma de fuego en dicho lugar, al tiempo \u00a0que \u00a0\u00e9l \u00a0autoriz\u00f3 \u00a0a \u00a0sus \u00a0subalternos \u00a0para \u00a0que \u00a0se \u00a0dirigieran a ese sitio. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Para \u00a0el \u00a0agente \u00a0de \u00a0la \u00a0Procuradur\u00eda \u00a0General \u00a0de la Naci\u00f3n, son \u00a0falsas \u00a0las \u00a0manifestaciones \u00a0del \u00a0deponente \u00a0hechas cuatro a\u00f1os despu\u00e9s de la \u00a0informaci\u00f3n \u00a0que \u00a0por \u00a0escrito \u00a0alleg\u00f3 \u00a0a \u00a0la Fiscal\u00eda General de la Naci\u00f3n, \u00a0\u00fanicamente \u00a0con \u00a0el \u00a0prop\u00f3sito \u00a0de \u00a0favorecer \u00a0a \u00a0los \u00a0procesados como bien lo \u00a0advirti\u00f3 \u00a0el \u00a0fallador \u00a0de \u00a0segunda instancia, lo que a su turno conllev\u00f3 a se \u00a0que \u00a0se ordenara la investigaci\u00f3n penal contra el entonces Capit\u00e1n Guzm\u00e1n por \u00a0haber faltado a la verdad en su testimonio. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Resalta \u00a0la importancia del testimonio del inmediato superior de los \u00a0uniformados \u00a0IJ. \u00a0Yandun \u00a0Mueses \u00a0Ricardo \u00a0Heli, \u00a0quien corrobor\u00f3 que \u00e9stos no \u00a0contaban \u00a0con \u00a0ning\u00fan \u00a0permiso \u00a0para \u00a0ausentarse \u00a0de sus puestos de trabajo, ni \u00a0otorgado por \u00e9l ni por otro oficial. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a02. \u00a0Al \u00a0referirse al segundo cargo precisa que no se observa ning\u00fan \u00a0cercenamiento \u00a0respecto \u00a0del contenido de la indagatoria de Luis Alberto Padilla \u00a0Zamboni, \u00a0pues \u00a0en \u00a0su primera declaraci\u00f3n manifest\u00f3 que la autorizaci\u00f3n para \u00a0ausentarse \u00a0de \u00a0su \u00a0puesto \u00a0que \u00a0estaba ubicado en la esquina de la estaci\u00f3n de \u00a0polic\u00eda \u00a0le \u00a0fue \u00a0referenciada \u00a0por \u00a0el \u00a0agente Garz\u00f3n Olaya pero luego en una \u00a0segunda \u00a0deponencia \u00a0dijo \u00a0que \u00a0la \u00a0autorizaci\u00f3n \u00a0se la dio el capit\u00e1n Guzm\u00e1n \u00a0Vargas quien comandaba la estaci\u00f3n para la \u00e9poca. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Avala \u00a0la \u00a0conclusi\u00f3n del Tribunal acerca de que en ning\u00fan momento \u00a0este \u00a0procesado cont\u00f3 con permiso de su superior para ausentarse de su lugar de \u00a0facci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a03. \u00a0Por \u00a0\u00faltimo, \u00a0en \u00a0lo \u00a0atinente \u00a0al \u00a0cargo por falso raciocinio, \u00a0afirma \u00a0el \u00a0Procurador \u00a0Delegado que no se advierte trasgresi\u00f3n a las reglas de \u00a0la \u00a0sana \u00a0cr\u00edtica \u00a0y \u00a0lo \u00a0que \u00a0emerge es que los procesados para el d\u00eda de los \u00a0hechos \u00a0abandonaron, uno su puesto en la alcald\u00eda, y el otro en la estaci\u00f3n de \u00a0polic\u00eda \u00a0del \u00a0municipio \u00a0de \u00a0Barbacoas, \u00a0a \u00a0sabiendas \u00a0que \u00a0para tal prop\u00f3sito \u00a0necesitaban \u00a0la \u00a0autorizaci\u00f3n \u00a0de \u00a0su \u00a0superior, \u00a0pero \u00a0en \u00a0el \u00a0caso de Padilla \u00a0Zamboni, \u00a0\u00e9ste \u00a0se \u00a0conform\u00f3 con lo que le indic\u00f3 el agente Garz\u00f3n acerca de \u00a0que \u00a0 el \u00a0 desplazamiento \u00a0 hab\u00eda \u00a0 sido \u00a0 autorizado \u00a0por \u00a0el \u00a0superior.\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Concluye \u00a0que \u00a0en \u00a0la \u00a0sentencia de segunda instancia no se aprecian \u00a0errores \u00a0de car\u00e1cter valorativo, sino que en sana aplicaci\u00f3n de los principios \u00a0de \u00a0la \u00a0l\u00f3gica \u00a0y \u00a0de \u00a0la \u00a0experiencia, \u00a0se lleg\u00f3 a la verdad relevada por los \u00a0medios \u00a0de \u00a0convicci\u00f3n, motivo por el cual solicita que no se case el fallo del \u00a031 de agosto de 2009 proferido por el Tribunal Superior Militar. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Son \u00a0dos los cargos planteados contra la \u00a0sentencia \u00a0del \u00a0Tribunal Superior Militar, uno por falso juicio de identidad, el \u00a0cual \u00a0recae \u00a0sobre el testimonio de Esteban Guzm\u00e1n al haber sido tergiversado y \u00a0la \u00a0indagatoria \u00a0del \u00a0procesado \u00a0por \u00a0haber \u00a0sido \u00a0cercenada, \u00a0y \u00a0otro por falso \u00a0raciocinio. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1. Falso Juicio de identidad \u00a0 \u00a0\u00a0<\/p>\n<p>La \u00a0indebida \u00a0apreciaci\u00f3n de la indagatoria \u00a0del \u00a0acusado \u00a0Luis \u00a0Alberto \u00a0Padilla Zamboni, la hace consistir el recurrente en \u00a0que \u00a0el Tribunal no tuvo en cuenta lo manifestado por \u00e9ste en el sentido de que \u00a0el \u00a0permiso \u00a0para ausentarse de su puesto de trabajo, lo dio por otorgado debido \u00a0a \u00a0que \u00a0el \u00a0d\u00eda \u00a0de \u00a0los \u00a0hechos \u00a0instantes \u00a0previos\u00a0 \u00a0a su ocurrencia, su \u00a0compa\u00f1ero \u00a0el \u00a0Ag. \u00a0\u00c1lvaro \u00a0Andr\u00e9s \u00a0Garz\u00f3n, \u00a0le dijo que la autorizaci\u00f3n ya \u00a0hab\u00eda sido concedida por el superior. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Advierte \u00a0la Sala que el fallador de segunda instancia al momento de \u00a0dar \u00a0por \u00a0probado \u00a0uno \u00a0de \u00a0los \u00a0elementos \u00a0del \u00a0delito \u00a0de \u00a0abandono de puesto, \u00a0consistente \u00a0en \u00a0que la ausencia del funcionario de su lugar de trabajo no est\u00e9 \u00a0mediada \u00a0por \u00a0el \u00a0permiso \u00a0del \u00a0superior, \u00a0se concentr\u00f3 en la situaci\u00f3n de uno \u00a0s\u00f3lo \u00a0de \u00a0los \u00a0acusados, \u00a0\u00c1lvaro \u00a0Andr\u00e9s \u00a0Garz\u00f3n, \u00a0cuyas \u00a0exculpaciones para \u00a0desligarse \u00a0de \u00a0responsabilidad \u00a0por \u00a0este punible se sustentaron en sus propias \u00a0atestaciones \u00a0y en las del entonces T.C Esteban Guzm\u00e1n, quien para la \u00e9poca de \u00a0los \u00a0hechos \u00a0se \u00a0encontraba \u00a0a \u00a0cargo \u00a0de \u00a0la estaci\u00f3n de polic\u00eda a la cual se \u00a0hallaban adscritos los dos uniformados procesados. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0efecto, \u00a0no tuvo en cuenta el Tribunal que las circunstancias en \u00a0las \u00a0que \u00a0se \u00a0ejecut\u00f3 \u00a0el delito t\u00edpicamente militar, divergen respecto de los \u00a0dos \u00a0sindicados, \u00a0a pesar de que frente a los delitos de concusi\u00f3n y privaci\u00f3n \u00a0ilegal \u00a0de \u00a0la \u00a0libertad, \u00a0que \u00a0en \u00a0principio \u00a0concursaron con el de abandono de \u00a0puesto, \u00a0puede \u00a0afirmarse \u00a0que \u00a0se \u00a0est\u00e1 \u00a0ante \u00a0un \u00a0mismo supuesto de hecho que \u00a0incluye \u00a0la \u00a0situaci\u00f3n \u00a0tanto de Padilla Zamboni como de Garz\u00f3n Olaya, pues no \u00a0se \u00a0reputa \u00a0lo mismo frente a este \u00faltimo comportamiento, habida cuenta que los \u00a0procesados \u00a0se \u00a0encontraban \u00a0prestando \u00a0servicio \u00a0en \u00a0lugares \u00a0diferentes y bajo \u00a0circunstancias \u00a0distintas, \u00a0siendo \u00a0Garz\u00f3n \u00a0Olaya \u00a0quien \u00a0supuestamente \u00a0pidi\u00f3 \u00a0permiso \u00a0para \u00a0trasladarse \u00a0al \u00a0lugar \u00a0de \u00a0los hechos estando en la estaci\u00f3n de \u00a0polic\u00eda, lugar en el que no se encontraba el aqu\u00ed recurrente. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Recu\u00e9rdese \u00a0que \u00a0en \u00a0el interrogatorio que Padilla Zamboni rindi\u00f3 \u00a0ante \u00a0la Corte Marcial el 3 de abril del a\u00f1o 2008, qued\u00f3 claro que para aqu\u00e9l \u00a015 \u00a0de \u00a0diciembre \u00a0de \u00a02003, \u00a0\u00e9l \u00a0se \u00a0encontraba \u00a0prestando \u00a0cuarto turno en la \u00a0alcald\u00eda \u00a0de \u00a0la \u00a0localidad \u00a0de \u00a0Barbacoas-Nari\u00f1o \u00a0y \u00a0no \u00a0en \u00a0la \u00a0estaci\u00f3n de \u00a0polic\u00eda, \u00a0lo \u00a0cual \u00a0fue corroborado con la prueba documental, consistente en el \u00a0libro \u00a0de \u00a0servicios, \u00a0sin que dicha circunstancia haya sido desvirtuada, por el \u00a0contrario, \u00a0se ha tenido como un hecho demostrado desde las etapas iniciales del \u00a0proceso. \u00a0\u00a0<\/p>\n<p>Tambi\u00e9n \u00a0que la funci\u00f3n del acusado era la \u00a0de \u00a0servir de escolta del alcalde pero no en forma permanente, motivo por el que \u00a0en \u00a0esas ocasiones quedaba de \u201cdisponible\u201d, debido a que no formaba parte de \u00a0ninguna \u00a0escuadra \u00a0con \u00a0el \u00a0fin \u00a0de \u00a0que \u00a0en \u00a0caso \u00a0dado \u00a0apoyara \u00a0patrullajes o \u00a0procedimientos, \u00a0raz\u00f3n \u00a0que \u00a0explica \u00a0por \u00a0qu\u00e9 \u00a0desde \u00a0el inicio, el procesado \u00a0manifest\u00f3 \u00a0que \u00a0estando \u00a0en \u00a0la esquina de la alcald\u00eda tom\u00e1ndose una gaseosa, \u00a0arrib\u00f3 \u00a0 el \u00a0 Ag. \u00a0Garz\u00f3n \u00a0indic\u00e1ndole \u00a0que \u00a0lo \u00a0acompa\u00f1ara \u00a0a \u00a0realizar \u00a0un \u00a0procedimiento a unas cuadras del sitio. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Las \u00a0anteriores \u00a0circunstancias \u00a0fueron al mismo tiempo corroboradas \u00a0por \u00a0\u00c1lvaro \u00a0Andr\u00e9s \u00a0Garz\u00f3n, \u00a0quien manifest\u00f3 que una vez obtuvo la supuesta \u00a0autorizaci\u00f3n \u00a0para \u00a0ausentarse, se dirigi\u00f3 a la alcald\u00eda para buscar apoyo de \u00a0alguno \u00a0de \u00a0lo \u00a0policiales \u00a0que \u00a0se \u00a0encontraran \u00a0disponibles, hallando en dicha \u00a0situaci\u00f3n \u00a0a \u00a0Luis \u00a0Alberto \u00a0Padilla \u00a0Zamboni, \u00a0quien se dispuso a acompa\u00f1arlo \u00a0luego \u00a0de \u00a0que \u00a0\u00e9l, \u00a0Garz\u00f3n \u00a0Olaya, \u00a0le \u00a0dijo que el procedimiento hab\u00eda sido \u00a0ordenado por el superior. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Como \u00a0 se \u00a0 se\u00f1al\u00f3, \u00a0la \u00a0situaci\u00f3n \u00a0de \u00a0Padilla \u00a0Zamboni, \u00a0en \u00a0lo \u00a0relacionado \u00a0con \u00a0el \u00a0punible \u00a0de \u00a0abandono \u00a0de \u00a0puesto, \u00a0dista de la de \u00c1lvaro \u00a0Andr\u00e9s \u00a0Garz\u00f3n, \u00a0dado que \u00e9ste s\u00ed se encontraba en la estaci\u00f3n de polic\u00eda, \u00a0lugar \u00a0al \u00a0que supuestamente lleg\u00f3 la informaci\u00f3n sobre una persona sospechosa \u00a0en \u00a0el \u00a0billar \u00a0\u201cAnorama\u201d, \u00a0por \u00a0lo que fue el policial que se hallaba en la \u00a0estaci\u00f3n, \u00a0 el \u00a0 que\u00a0 \u00a0 solicit\u00f3 \u00a0el \u00a0permiso \u00a0por \u00a0ser \u00a0all\u00ed \u00a0donde \u00a0se \u00a0concentraban los mandos superiores. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0As\u00ed \u00a0 las \u00a0 cosas, \u00a0el \u00a0conocimiento \u00a0sobre \u00a0la \u00a0existencia \u00a0de \u00a0la \u00a0autorizaci\u00f3n \u00a0lleg\u00f3 \u00a0a \u00a0Padilla \u00a0Zamboni \u00a0por lo que le manifest\u00f3 el tambi\u00e9n \u00a0policial \u00a0Garz\u00f3n Olaya, seg\u00fan lo ha indicado el propio acusado y su compa\u00f1ero \u00a0de \u00a0causa \u00a0coincidiendo \u00a0en \u00a0ese \u00a0aspecto \u00a0desde sus primeras salidas procesales \u00a0producidas \u00a0en el a\u00f1o 2007, incluyendo el interrogatorio rendido por ambos ante \u00a0la \u00a0Corte Marcial en el a\u00f1o 2008, sin que emerja prueba que se\u00f1ale que\u00a0 a \u00a0Padilla \u00a0Zamboni \u00a0su compa\u00f1ero Garz\u00f3n no le dijo nada de la autorizaci\u00f3n para \u00a0ausentarse, \u00a0pese \u00a0a lo cual decidi\u00f3 evadirse, o que el procesado no lo indag\u00f3 \u00a0al respecto y voluntariamente se march\u00f3 del lugar de trabajo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a0Tribunal \u00a0partiendo \u00a0del \u00a0supuesto \u00a0de \u00a0que Garz\u00f3n Olaya s\u00ed le \u00a0manifest\u00f3 \u00a0al \u00a0patrullero \u00a0Padilla \u00a0Zamboni \u00a0que hab\u00eda obtenido el permiso, de \u00a0todas \u00a0formas \u00a0le reprocha a este \u00faltimo que no haya confirmado lo indicado por \u00a0su \u00a0compa\u00f1ero, \u00a0reclamo que a criterio de la Sala no resulta exigible dadas las \u00a0particularidades \u00a0del \u00a0caso, \u00a0en donde Garz\u00f3n Olaya ten\u00eda un grado superior al \u00a0del \u00a0acusado \u00a0pues era agente, mientras que Padilla Zamboni se desempe\u00f1aba como \u00a0patrullero \u00a0y \u00a0se encontraba en el a\u00f1o de periodo de prueba luego de su ingreso \u00a0a \u00a0la \u00a0instituci\u00f3n, \u00a0frente \u00a0a los doce a\u00f1os de experiencia que ten\u00eda Garz\u00f3n \u00a0Olaya \u00a0como \u00a0miembro de la Polic\u00eda Nacional, dado que es sabido que al interior \u00a0de \u00a0la \u00a0instituci\u00f3n \u00a0castrense \u00a0el \u00a0rango \u00a0y \u00a0la \u00a0antig\u00fcedad \u00a0se \u00a0traducen \u00a0en \u00a0obediencia \u00a0 \u00a0de \u00a0 \u00a0los \u00a0 \u00a0inferiores \u00a0 \u00a0hacia \u00a0 \u00a0sus \u00a0 compa\u00f1eros \u00a0 de \u00a0 rango \u00a0superior. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0tal \u00a0medida, \u00a0no \u00a0le \u00a0era reprochable al acusado que simplemente \u00a0creyera \u00a0en \u00a0lo \u00a0que le dijo Garz\u00f3n Olaya para dar por obtenido el permiso para \u00a0ausentarse \u00a0de \u00a0su puesto ubicado en la alcald\u00eda, pues de lo contrario, ante la \u00a0desconfianza \u00a0que \u00a0pod\u00eda \u00a0generarle \u00a0lo \u00a0atestado \u00a0por el agente Garz\u00f3n, se le \u00a0impon\u00eda \u00a0la \u00a0obligaci\u00f3n \u00a0de \u00a0devolverse \u00a0hasta \u00a0la \u00a0Estaci\u00f3n \u00a0de \u00a0Polic\u00eda \u00a0y \u00a0preguntarle \u00a0a \u00a0sus \u00a0superiores si era cierto lo que le dijo su compa\u00f1ero sobre \u00a0la autorizaci\u00f3n para retirarse de su lugar de labores. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Dentro \u00a0del \u00a0proceso \u00a0no concurre medio de convicci\u00f3n del que pueda \u00a0derivarse \u00a0que \u00a0Padilla \u00a0Zamboni deb\u00eda desconfiar del agente Garz\u00f3n, como para \u00a0proceder \u00a0a \u00a0corroborar \u00a0la \u00a0presunta orden que hab\u00eda dado el entonces Capit\u00e1n \u00a0Guzm\u00e1n o el Sargento Yandun, seg\u00fan lo indic\u00f3 Garz\u00f3n Olaya. \u00a0\u00a0<\/p>\n<p>Si \u00a0bien \u00a0es \u00a0cierto, \u00a0luego \u00a0de \u00a0que \u00a0ambos \u00a0procesados \u00a0se \u00a0retiraron \u00a0de sus lugares de asignaci\u00f3n, se vieron envueltos en \u00a0la \u00a0comisi\u00f3n \u00a0de \u00a0otros \u00a0delitos \u00a0por \u00a0los \u00a0que al parecer fueron condenados en \u00a0calidad \u00a0de \u00a0coautores, esa forma de intervenci\u00f3n mancomunada en los delitos de \u00a0privaci\u00f3n \u00a0ilegal de la libertad y concusi\u00f3n, mal podr\u00eda extenderse al delito \u00a0de \u00a0abandono \u00a0de \u00a0puesto, \u00a0en orden a concluir que el plan criminal se orquest\u00f3 \u00a0desde \u00a0el \u00a0momento \u00a0mismo \u00a0en \u00a0que \u00a0para \u00a0apoderarse de una suma de dinero de un \u00a0ciudadano \u00a0que \u00a0se \u00a0encontraba en el billar \u201cAnorama\u201d, los acusados debieron \u00a0planear \u00a0la \u00a0forma \u00a0de \u00a0evadirse de su lugar de trabajo, pues no existe medio de \u00a0convicci\u00f3n \u00a0si \u00a0quiera \u00a0indiciario \u00a0que \u00a0as\u00ed \u00a0lo \u00a0acredite \u00a0y \u00a0de afirmarse lo \u00a0contrario ello obedecer\u00eda a meras conjeturas.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Lo \u00a0anterior, \u00a0habida cuenta que lo mostrado \u00a0por \u00a0 los \u00a0 medios \u00a0de \u00a0convicci\u00f3n, \u00a0es \u00a0que \u00a0el \u00a0traslado \u00a0hacia \u00a0el \u00a0referido \u00a0establecimiento \u00a0de comercio obedeci\u00f3 a la informaci\u00f3n sobre un sospechoso que \u00a0portaba \u00a0 un \u00a0arma \u00a0de \u00a0fuego, \u00a0conoci\u00e9ndose \u00a0la \u00a0existencia \u00a0del \u00a0dinero \u00a0cuya \u00a0procedencia \u00a0fue \u00a0calificada \u00a0de \u00a0il\u00edcita \u00a0por \u00a0los \u00a0policiales, s\u00f3lo hasta el \u00a0momento \u00a0en \u00a0el \u00a0que \u00a0se \u00a0efectu\u00f3 \u00a0la requisa, instante en el que se inici\u00f3 la \u00a0ejecuci\u00f3n \u00a0asociada \u00a0de \u00a0los punibles contra la libertad individual y contra la \u00a0administraci\u00f3n \u00a0p\u00fablica, \u00a0pero \u00a0sin \u00a0que \u00a0el \u00a0plan \u00a0de autor desplegado por el \u00a0patrullero \u00a0Padilla Zamboni y el agente Garz\u00f3n Olaya, haya incluido la evasi\u00f3n \u00a0de \u00a0sus \u00a0puestos \u00a0de \u00a0trabajo, \u00a0mucho \u00a0m\u00e1s \u00a0respecto \u00a0del primero cuando lo que \u00a0informa \u00a0el proceso es que Garz\u00f3n Olaya se traslad\u00f3 a la alcald\u00eda a buscar el \u00a0apoyo \u00a0de un polic\u00eda que estuviera disponible, sin que las pruebas se\u00f1alen que \u00a0fue \u00a0espec\u00edficamente \u00a0por \u00a0Padilla \u00a0Zamboni \u00a0como \u00a0para \u00a0deducir que se puso de \u00a0acuerdo \u00a0con \u00a0Garz\u00f3n \u00a0Olaya para faltar a la ley penal desde antes de llegar al \u00a0billar \u00a0\u201cAnorama\u201d \u00a0y \u00a0por \u00a0tanto, incluir en esa intenci\u00f3n criminal, por lo \u00a0menos \u00a0en \u00a0lo que se refiere a Padilla Zamboni, el delito de abandono de puesto. \u00a0\u00a0<\/p>\n<p>De \u00a0haber \u00a0el \u00a0Tribunal tenido en cuenta los \u00a0apartes \u00a0de \u00a0lo \u00a0manifestado \u00a0por \u00a0Padilla Zamboni y Garz\u00f3n Olaya en sus varias \u00a0salidas \u00a0procesales, \u00a0sobre los motivos que los llevaron a abandonar sus lugares \u00a0de \u00a0trabajo, \u00a0habr\u00eda \u00a0advertido \u00a0que \u00a0se trat\u00f3 de razones diferentes para cada \u00a0uno, \u00a0por \u00a0encontrarse \u00a0en \u00a0circunstancias \u00a0distintas, \u00a0de \u00a0donde \u00a0la \u00a0falta \u00a0de \u00a0credibilidad \u00a0que \u00a0le mereci\u00f3 el testimonio de Esteban Guzm\u00e1n cuando confirm\u00f3 \u00a0que \u00a0en \u00a0efecto \u00a0le \u00a0hab\u00eda dado permiso a Garz\u00f3n Olaya para dirigirse hacia el \u00a0billar \u00a0en \u00a0compa\u00f1\u00eda \u00a0de \u00a0otro \u00a0policial que le prestara apoyo y que estuviera \u00a0disponible \u00a0en \u00a0la \u00a0alcald\u00eda, s\u00f3lo puede tener consecuencias para rechazar las \u00a0exculpaciones \u00a0de \u00a0Garz\u00f3n \u00a0Olaya \u00a0frente \u00a0al delito militar, a cuyo dicho el ad \u00a0quem \u00a0tampoco \u00a0le \u00a0otorg\u00f3 \u00a0fuerza demostrativa al concluir que estaba mintiendo \u00a0por \u00a0las \u00a0varias \u00a0contradicciones \u00a0en \u00a0las \u00a0que \u00a0incurri\u00f3, \u00a0sumadas a las de su \u00a0entonces superior y comandante de estaci\u00f3n Esteban Guzm\u00e1n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0tal \u00a0medida, \u00a0s\u00ed advierte la Corte una apreciaci\u00f3n sesgada por \u00a0parte \u00a0del Tribunal Militar de las exculpaciones expuestas por el sindicado Luis \u00a0Alberto \u00a0Padilla \u00a0Zamboni \u00a0que \u00a0de haber sido consideradas y confrontadas con lo \u00a0dicho \u00a0por \u00a0su \u00a0compa\u00f1ero \u00a0acerca de que \u00e9l le adujo a Padilla Zamboni que s\u00ed \u00a0ten\u00edan \u00a0el \u00a0permiso, \u00a0habr\u00edan \u00a0permitido \u00a0advertir \u00a0una duda sobre la voluntad \u00a0dolosa \u00a0del \u00a0acusado \u00a0de \u00a0ausentarse \u00a0de \u00a0su \u00a0lugar \u00a0de \u00a0trabajo \u00a0sin contar con \u00a0autorizaci\u00f3n, \u00a0con \u00a0la finalidad de cometer otros delitos contra ciudadanos del \u00a0municipio \u00a0de Barbacoas-Nari\u00f1o conforme a un plan criminal previamente acordado \u00a0con \u00a0el \u00a0Ag. \u00a0Garz\u00f3n \u00a0Olaya, \u00a0pues \u00a0no \u00a0concurre elemento de juicio que as\u00ed lo \u00a0acredite. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Lo \u00a0que los medios de convicci\u00f3n informan es que el 15 de diciembre \u00a0los \u00a0dos \u00a0policiales ejecutaron los delitos de concusi\u00f3n y privaci\u00f3n ilegal de \u00a0la \u00a0libertad, \u00a0movidos \u00a0por \u00a0el \u00a0\u00e1nimo \u00a0de apoderarse del dinero en efectivo de \u00a0propiedad \u00a0de un ciudadano de la localidad, para lo cual debieron desplazarse de \u00a0sus \u00a0sitios \u00a0de \u00a0trabajo. \u00a0Y sobre el permiso con el que ten\u00edan que contar para \u00a0retirarse \u00a0del puesto, en lo relacionado con Luis Alberto Padilla, \u00e9ste confi\u00f3 \u00a0en \u00a0lo \u00a0que \u00a0al \u00a0parecer le dijo su compa\u00f1ero sobre que el procedimiento hab\u00eda \u00a0sido \u00a0autorizado \u00a0por su superior, pero frente a lo manifestado por el Ag. Olaya \u00a0Garz\u00f3n \u00a0el \u00a0Tribunal \u00a0hizo \u00a0un razonamiento que lo llev\u00f3 a afirmar que \u00e9ste y \u00a0Esteban \u00a0Garz\u00f3n \u00a0mintieron \u00a0sobre \u00a0la existencia de la mentada autorizaci\u00f3n lo \u00a0que \u00a0motiv\u00f3 \u00a0la \u00a0iniciaci\u00f3n de una investigaci\u00f3n penal por el delito de falso \u00a0testimonio \u00a0contra \u00a0el \u00a0\u00faltimo, \u00a0raz\u00f3n por la que el fallo condenatorio contra \u00a0\u00c1lvaro \u00a0Andr\u00e9s \u00a0Garz\u00f3n \u00a0Olaya \u00a0por \u00a0el \u00a0punible \u00a0de \u00a0abandono \u00a0de \u00a0puesto \u00a0se \u00a0mantendr\u00e1. \u00a0\u00a0<\/p>\n<p>La \u00a0conclusi\u00f3n \u00a0del Tribunal en tal sentido \u00a0claramente \u00a0alude \u00a0a \u00a0la \u00a0responsabilidad \u00a0de \u00a0Garz\u00f3n \u00a0Olaya \u00a0en la conducta de \u00a0abandono \u00a0de \u00a0puesto, \u00a0sin \u00a0que \u00a0la \u00a0misma \u00a0pueda \u00a0extenderse a la situaci\u00f3n de \u00a0Padilla \u00a0Zamboni\u00a0 al emerger la posibilidad de que su ausencia del lugar de \u00a0labores, \u00a0estuviera \u00a0mediada \u00a0por el errado convencimiento acerca de que contaba \u00a0con \u00a0el \u00a0permiso \u00a0del superior para el efecto de acuerdo con la informaci\u00f3n que \u00a0le \u00a0suministr\u00f3 \u00a0el \u00a0Ag. \u00a0\u00c1lvaro \u00a0Andr\u00e9s \u00a0Garz\u00f3n \u00a0Olaya, \u00a0probabilidad que se \u00a0mantiene \u00a0ante \u00a0la \u00a0inexistencia \u00a0de \u00a0prueba \u00a0que \u00a0acredite \u00a0lo \u00a0contrario y por \u00a0contera, \u00a0la \u00a0presencia \u00a0de \u00a0una \u00a0duda \u00a0que \u00a0habr\u00e1 \u00a0de \u00a0resolverse \u00a0a favor del \u00a0procesado, \u00a0sin que ello implique una apreciaci\u00f3n encaminada a desligarlo de la \u00a0responsabilidad \u00a0penal \u00a0que \u00a0le fue atribuida por la justicia ordinaria frente a \u00a0las \u00a0conductas \u00a0de \u00a0privaci\u00f3n \u00a0ilegal de la libertad y concusi\u00f3n, dado que las \u00a0mismas \u00a0aunque \u00a0fueron \u00a0ejecutadas \u00a0con \u00a0posterioridad inmediata a la del delito \u00a0militar, \u00a0no \u00a0lo \u00a0fueron en su s\u00f3lo acto conjunto con la de abandono de puesto, \u00a0cuyo \u00a0momento \u00a0y circunstancias de comisi\u00f3n resultan claramente diferenciables, \u00a0respecto de los dos primeros punibles. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0As\u00ed \u00a0las \u00a0cosas advierte la Sala un error de hecho por falso juicio \u00a0de \u00a0identidad por cercenamiento, lo cual conllev\u00f3 a la falta de aplicaci\u00f3n del \u00a0art\u00edculo \u00a0209 \u00a0del \u00a0C\u00f3digo \u00a0Penal \u00a0Militar \u00a0y \u00a0a \u00a0la \u00a0indebida aplicaci\u00f3n del \u00a0art\u00edculo \u00a0124 \u00a0de \u00a0la \u00a0misma normatividad que tipifica el delito de abandono de \u00a0puesto. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0s\u00edntesis, \u00a0el cargo prospera dando lugar a que la sentencia del \u00a0Tribunal \u00a0Superior \u00a0Militar \u00a0sea \u00a0casada, \u00a0procediendo \u00a0la emisi\u00f3n del fallo de \u00a0reemplazo \u00a0en \u00a0el \u00a0sentido de absolver a Luis Alberto Padilla Zamboni del delito \u00a0de \u00a0abandono \u00a0de \u00a0puesto.\u00a0 \u00a0Por \u00a0sustracci\u00f3n \u00a0de materia los dem\u00e1s cargos \u00a0postulados \u00a0en \u00a0el \u00a0libelo \u00a0referidos \u00a0a \u00a0la \u00a0violaci\u00f3n \u00a0indirecta \u00a0de \u00a0la \u00a0ley \u00a0sustancial \u00a0por \u00a0falso \u00a0juicio \u00a0de \u00a0identidad \u00a0y raciocino,\u00a0 no ameritan el \u00a0an\u00e1lisis \u00a0de la Corte, pues al prosperar la primera censura \u00e9sta es suficiente \u00a0para \u00a0desquiciar \u00a0el \u00a0fallo \u00a0proferido \u00a0en \u00a0segunda \u00a0instancia \u00a0por \u00a0el Tribunal \u00a0Superior Militar. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n Penal de la Corte Suprema de Justicia, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 \u00a0<\/p>\n<p>CASAR\u00a0 \u00a0la \u00a0sentencia \u00a0del \u00a031 \u00a0de \u00a0agosto de 2009 a trav\u00e9s de la cual el Tribunal Superior \u00a0Militar \u00a0hab\u00eda \u00a0condenado \u00a0a \u00a0Luis \u00a0Alberto \u00a0Padilla \u00a0Zamboni \u00a0por el delito de \u00a0abandono de puesto para en su lugar absolverlo de esa conducta. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta \u00a0decisi\u00f3n \u00a0no \u00a0procede recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>Comun\u00edquese \u00a0y \u00a0devu\u00e9lvase \u00a0al Tribunal de \u00a0origen. C\u00famplase \u00a0\u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0<\/p>\n<p>Permiso \u00a0<\/p>\n<p>JOSE \u00a0LUIS \u00a0BARCEL\u00d3 \u00a0CAMACHO \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0FERNANDO \u00a0A \u00a0CASTRO \u00a0 \u00a0CABALLERO \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>SIGIFREDO \u00a0ESPINOSA \u00a0P\u00c9REZ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 MARIA \u00a0DEL \u00a0ROSARIO \u00a0GONZ\u00c1LEZ \u00a0MU\u00d1OZ \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>AUGUSTO \u00a0J. \u00a0IBA\u00d1EZ \u00a0GUZM\u00c1N \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0LUIS \u00a0GUILLERMO SALAZAR OTERO \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JULIO ENRIQUE SOCHA SALAMANCA \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0JAVIER ZAPATA ORTIZ \u00a0\u00a0<\/p>\n<p>NUBIA YOLANDA NOVA GARC\u00cdA \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso n\u00ba 33486 \u00a0 CORTE SUPRE MA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente: \u00a0 FERNANDO \u00a0ALBERTO \u00a0CASTRO \u00a0CABALLERO \u00a0\u00a0 Aprobado \u00a0 \u00a0Acta \u00a0N\u00b0155 \u00a0\u00a0 Bogot\u00e1, \u00a0D. \u00a0C., dos (2) de mayo de dos mil \u00a0dos doce (2012). \u00a0\u00a0 VISTOS \u00a0 Procede \u00a0la \u00a0Sala \u00a0a \u00a0emitir \u00a0el \u00a0fallo \u00a0de \u00a0casaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-23482","post","type-post","status-publish","format-standard","hentry","category-20"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/23482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=23482"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/23482\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=23482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=23482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=23482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}