{"id":2249,"date":"2023-09-07T21:28:29","date_gmt":"2023-09-07T21:28:29","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/07\/15269j\/"},"modified":"2023-09-07T21:28:29","modified_gmt":"2023-09-07T21:28:29","slug":"15269j","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/07\/15269j\/","title":{"rendered":"15269j"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No. 15269 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CORTE SUPREMA DE JUSTICIA \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0SALA DE CASACION PENAL \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Magistrado Ponente \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0DR. CARLOS AUGUSTO GALVEZ ARGOTE \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Aprobado Acta No.115 \u00a0\u00a0<\/p>\n<p>Santaf\u00e9 de Bogot\u00e1, D.C., tres (3) de agosto \u00a0de mil novecientos noventa y nueve (1.999). \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0VISTOS: \u00a0\u00a0<\/p>\n<p>Se \u00a0pronuncia la Sala sobre la admisibilidad \u00a0formal \u00a0de \u00a0la \u00a0demanda de casaci\u00f3n presentada por el defensor de MARTIN ALONSO \u00a0AMAYA \u00a0LEON \u00a0contra \u00a0de la sentencia del Tribunal Superior del Distrito Judicial \u00a0de \u00a0C\u00facuta \u00a0de \u00a0fecha 3 de agosto de 1.998, mediante la cual confirm\u00f3 el fallo \u00a0emitido \u00a0por \u00a0el Juzgado Cuarto Penal del Circuito de esa ciudad que lo conden\u00f3 \u00a0a \u00a0la \u00a0pena principal de 25 a\u00f1os y 2 meses de prisi\u00f3n, como responsable de los \u00a0delitos \u00a0 de \u00a0 homicidio \u00a0 y \u00a0 porte \u00a0 ilegal \u00a0de \u00a0armas \u00a0de \u00a0fuego \u00a0de \u00a0defensa \u00a0personal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0HECHOS: \u00a0\u00a0<\/p>\n<p>Los \u00a0sintetiza \u00a0el \u00a0Tribunal \u00a0Superior en la \u00a0sentencia impugnada, as\u00ed: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0&#8220;Sucedieron \u00a0el 12 de Junio de 1.994, hacia las 7:00 de la noche en \u00a0el \u00a0Barrio \u00a0Ospina \u00a0P\u00e9rez \u00a0de esta ciudad. All\u00ed RAFAEL ALCOCER BAYONA, postrer \u00a0v\u00edctima, \u00a0transitaba \u00a0por la avenida 5a.en una bicicleta y al llegar a la calle \u00a023 \u00a0 se \u00a0 encontr\u00f3\u00a0 \u00a0con\u00a0 \u00a0DAGOBERTO\u00a0 \u00a0ALSINA \u00a0LEON, \u00a0TEODOBERTO \u00a0CONTRERAS\u00a0 \u00a0LEON\u00a0 \u00a0y MARTIN\u00a0 ALONSO AMAYA LEON, present\u00e1ndose un \u00a0altercado \u00a0entre \u00a0RAFAEL \u00a0ALCOCER \u00a0BAYONA \u00a0y \u00a0ALSINA \u00a0LEON,interviniendo \u00a0el hoy \u00a0procesado \u00a0MARTIN \u00a0ALONSO AMAYA LEON, quien accion\u00f3 el arma de fuego, rev\u00f3lver \u00a0calibre \u00a038 \u00a0largo, \u00a0marca \u00a0Colt, identificado con el n\u00famero 49100R, resultando \u00a0herido \u00a0RAFAEL ALCOCER BAYONA, quien falleci\u00f3 cuando era trasladado al Hospital \u00a0ERASMO \u00a0MEOZ, \u00a0donde \u00a0se llev\u00f3 a cabo la inspecci\u00f3n judicial con levantamiento \u00a0del cad\u00e1ver&#8221;. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0DEMANDA: \u00a0\u00a0<\/p>\n<p>Contra \u00a0la \u00a0sentencia \u00a0impugnada, \u00a0un \u00a0cargo \u00a0propone \u00a0el \u00a0defensor \u00a0de \u00a0MARTIN \u00a0ALONSO AMAYA LEON con fundamento en el cuerpo \u00a0segundo \u00a0de \u00a0la causal primera del art. 220 del C. de P.P. &#8220;por error sustancial \u00a0indirecto de la norma&#8221;. \u00a0\u00a0<\/p>\n<p>Para \u00a0sustentar el reparo, comienza el actor \u00a0por \u00a0afirmar que en sana cr\u00edtica habr\u00eda el Tribunal errado en la valoraci\u00f3n y \u00a0apreciaci\u00f3n \u00a0de la prueba de cargo as\u00ed como de las injuradas de los sindicados \u00a0dejando \u00a0de \u00a0lado, \u00a0igualmente, \u00a0algunos\u00a0 \u00a0aspectos \u00a0de importancia para el \u00a0proceso, \u00a0con \u00a0evidente \u00a0violaci\u00f3n \u00a0de \u00a0los arts. 241, 248, 250 y 254 del C. de \u00a0P.P., \u00a0cuyo \u00a0texto \u00a0reproduce, haciendo lo propio\u00a0 con algunos extractos de \u00a0diversas \u00a0decisiones de esta Sala sobre los requisitos para condenar, la validez \u00a0de la prueba y el testigo \u00fanico, que estima pertinentes al caso. \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 \u00a0<\/p>\n<p>Enseguida \u00a0y sobre la base de que la &#8220;prueba \u00a0reina&#8221; \u00a0para condenar a AMAYA LEON en este proceso lo habr\u00eda sido el testimonio \u00a0del \u00a0menor \u00a0Sergio \u00a0Humberto \u00a0Palencia \u00a0por ser &#8220;coherente y ver\u00e1z&#8221;, recuerda y \u00a0transcribe \u00a0los \u00a0argumentos \u00a0expuestos \u00a0por \u00a0la \u00a0defensa \u00a0en las instancias para \u00a0demostrar \u00a0lo contrario, pues en su criterio se trata de &#8220;simples especulaciones \u00a0sin \u00a0asidero probatorio alguno&#8221;, dentro del cual se aprecian m\u00faltiples &#8220;yerros, \u00a0vac\u00edos \u00a0y \u00a0contradicciones&#8221;, al que se opone las ampliaciones de la injurada de \u00a0su \u00a0defenido, \u00a0como \u00a0las \u00a0declaraciones \u00a0de \u00a0los \u00a0familiares \u00a0de \u00a0\u00e9ste \u00a0que \u00a0la \u00a0respaldan, \u00a0tales \u00a0como \u00a0las \u00a0de \u00a0sus primos Dagoberto Alsina Le\u00f3n y Teodoberto \u00a0Contreras Le\u00f3n. \u00a0\u00a0<\/p>\n<p>Precisa, \u00a0entonces, que ha debido cre\u00e9rsele \u00a0al \u00a0procesado \u00a0cuando \u00a0sostuvo \u00a0con \u00a0posterioridad \u00a0a \u00a0su primera versi\u00f3n, pues \u00a0tambi\u00e9n \u00a0fue \u00a0expl\u00edcito \u00a0en \u00a0que \u00a0dentro \u00a0de \u00a0esta \u00a0diligencia \u00a0se \u00a0encontraba \u00a0atemorizado \u00a0por \u00a0un \u00a0hermano de la v\u00edctima, que Rafael Alc\u00f3cer Bayona hizo un \u00a0adem\u00e1n \u00a0de \u00a0sacar \u00a0algo del bolsillo del pantal\u00f3n, siendo este hecho el que lo \u00a0motiv\u00f3 a accionar en su contra el rev\u00f3lver que portaba. \u00a0\u00a0<\/p>\n<p>De \u00a0esta manera, concluye el censor, si bien \u00a0la \u00a0muerte \u00a0de \u00a0Bayona es algo objetivamente incuestionable &#8220;contin\u00faa en gracia \u00a0de \u00a0discusi\u00f3n, \u00a0si \u00a0respecto al factor responsabilidad obra prueba en contrario \u00a0que \u00a0la desvirt\u00fae&#8221;, lo cual en su concepto merece respuesta positiva ya que con \u00a0base \u00a0en \u00a0los \u00a0distintos \u00a0elementos \u00a0probatorios \u00a0allegados se establece el real \u00a0decurso \u00a0de \u00a0los \u00a0acontecimientos \u00a0y \u00a0por ende, la concurrencia de una causal de \u00a0inculpabilidad \u00a0 (art. \u00a0 40.3 \u00a0 del \u00a0 C.P.) \u00a0 o \u00a0 inclusive, \u00a0 de \u00a0un \u00a0homicidio \u00a0preterintencional, \u00a0tesis que recuerda tampoco fuera aceptada por los juzgadores \u00a0en las instancias. \u00a0\u00a0<\/p>\n<p>Solicita, \u00a0en \u00a0consecuencia, \u00a0se \u00a0case \u00a0la \u00a0sentencia \u00a0impugnada \u00a0y \u00a0&#8220;en \u00a0su \u00a0defecto se profiera la que deba reemplazarla&#8221;. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0CONSIDERACIONES: \u00a0\u00a0<\/p>\n<p>1. \u00a0Postulado \u00a0el \u00a0ataque \u00a0que \u00a0a \u00a0la \u00a0sentencia \u00a0de \u00a0segunda \u00a0instancia \u00a0objeto de la impugnaci\u00f3n \u00a0extraordinaria \u00a0ha \u00a0propuesto \u00a0el \u00a0defensor \u00a0de \u00a0MARTIN \u00a0ALONSO AMAYA LEON en el \u00a0\u00fanico \u00a0cargo \u00a0esgrimido, \u00a0bajo \u00a0el supuesto de la primera causal, cuerpo segundo, del art\u00edculo 220 del C. \u00a0de \u00a0P.P. \u00a0acusando \u00a0la \u00a0existencia \u00a0de errores de hecho, con miras a deslindar a \u00a0cu\u00e1l \u00a0 de \u00a0 las \u00a0 distintas \u00a0alternativas \u00a0que \u00a0el \u00a0error \u00a0sustancial \u00a0f\u00e1ctico \u00a0te\u00f3ricamente \u00a0admite, \u00a0ha \u00a0debido \u00a0el \u00a0demandante \u00a0esclarecer \u00a0con precisi\u00f3n y \u00a0claridad \u00a0si el fallador para sustentar la condena ignor\u00f3, tergivers\u00f3 o supuso \u00a0alg\u00fan \u00a0 medio \u00a0 probatorio, \u00a0 siendo \u00a0 imperativo \u00a0en \u00a0cada \u00a0caso \u00a0el \u00a0concreto \u00a0se\u00f1alamiento \u00a0del \u00a0mismo, as\u00ed como tambi\u00e9n evidenciar la trascendencia que la \u00a0falencia \u00a0acusada \u00a0representa \u00a0con \u00a0miras \u00a0a \u00a0una \u00a0decisi\u00f3n \u00a0m\u00e1s \u00a0favorable al \u00a0procesado. \u00a0\u00a0<\/p>\n<p>2. Sin embargo, no \u00a0ha \u00a0 orientado \u00a0la \u00a0censura \u00a0el \u00a0demandante \u00a0bajo \u00a0ninguno \u00a0de \u00a0los \u00a0denominados \u00a0t\u00e9cnicamente \u00a0falsos \u00a0juicios \u00a0de \u00a0existencia \u00a0e \u00a0identidad \u00a0a \u00a0que se ha hecho \u00a0referencia \u00a0o \u00a0una equivalente o de igual significaci\u00f3n que permitiera entender \u00a0el \u00a0verdadero \u00a0enfoque \u00a0del \u00a0ataque \u00a0pretendido \u00a0contra \u00a0el fallo, pues salvo el \u00a0calificativo \u00a0que \u00a0confusamente \u00a0al \u00a0mismo da de constituir un &#8220;error sustancial \u00a0indirecto \u00a0de \u00a0la \u00a0norma&#8221;, \u00a0en \u00a0forma \u00a0concreta \u00a0los \u00a0reparos \u00a0se han dirigido a \u00a0cuestionar \u00a0la \u00a0credibilidad \u00a0que para los sentenciadores mereci\u00f3 el testimonio \u00a0del \u00a0menor \u00a0Sergio Humberto Palencia por cuanto en su criterio en el an\u00e1lisis y \u00a0valoraci\u00f3n \u00a0del \u00a0mismo \u00a0no \u00a0habr\u00eda \u00a0acertado \u00a0el Tribunal, pues contrariamente \u00a0merec\u00edan \u00a0respaldo \u00a0las \u00a0afirmaciones \u00a0injuradas \u00a0del \u00a0inculpado \u00a0y el grupo de \u00a0familiares que lo apoyaban en su dicho. \u00a0\u00a0<\/p>\n<p>3. \u00a0Siendo \u00a0ello \u00a0as\u00ed, \u00a0se \u00a0torna \u00a0verdaderamente \u00a0injustificada y gratuita la menci\u00f3n que de la \u00a0causal \u00a0primera de casaci\u00f3n en su segundo supuesto hace el actor, visto como se \u00a0deja \u00a0que \u00a0en \u00a0el \u00a0fondo \u00a0el \u00a0alegato \u00a0realmente esgrimido no dice referencia al \u00a0sentido \u00a0objetivo \u00a0de \u00a0la \u00a0prueba \u00a0que \u00a0en \u00a0alguna de las indicadas alternativas \u00a0tendr\u00eda \u00a0que \u00a0haberse \u00a0presentado como vicio atacable en esta sede, sino con el \u00a0valor \u00a0que \u00a0a \u00a0la misma le diera el fallador, cuando este es un aspecto sobre el \u00a0cual \u00a0mientras \u00a0no se atente contra los principios de la sana cr\u00edtica, no puede \u00a0recaer \u00a0 \u00a0 ning\u00fan \u00a0 \u00a0reparo \u00a0 \u00a0a \u00a0 \u00a0trav\u00e9s \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0impugnaci\u00f3n \u00a0 \u00a0extr \u00a0saordinaria. \u00a0\u00a0<\/p>\n<p>4. Pero adem\u00e1s, la \u00a0ineptitud \u00a0formal \u00a0de \u00a0la \u00a0demanda \u00a0se \u00a0ve \u00a0reflejada \u00a0con mayor evidencia en la \u00a0abierta \u00a0oposici\u00f3n \u00a0que \u00a0expresa \u00a0el \u00a0actor \u00a0entre la credibilidad que para \u00e9l \u00a0merecen \u00a0las \u00a0exculpaciones \u00a0del procesado y el grado de convicci\u00f3n que a ellas \u00a0otorgara \u00a0 el \u00a0 sentenciador, \u00a0 con \u00a0la \u00a0inesperada, \u00a0confusa \u00a0y \u00a0contradictoria \u00a0proposici\u00f3n \u00a0jur\u00eddica \u00a0de \u00a0que podr\u00edan concurrir una causal de inculpabilidad \u00a0(art. \u00a040.3 \u00a0del \u00a0C.P.) \u00a0o \u00a0inclusive, \u00a0el \u00a0delito \u00a0contra \u00a0la vida e integridad \u00a0personal \u00a0pero bajo una imputaci\u00f3n preterintencional, cuando en ning\u00fan momento \u00a0se \u00a0 emplearon \u00a0 esfuerzos \u00a0 en \u00a0 la \u00a0 demostraci\u00f3n \u00a0de \u00a0alguna \u00a0de \u00a0estas \u00a0dos \u00a0figuras. \u00a0\u00a0<\/p>\n<p>En \u00a0estas \u00a0condiciones \u00a0y \u00a0al \u00a0no cumplir la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada a nombre de MARTIN ALONSO AMAYA LEON, con los \u00a0requisitos \u00a0exigidos \u00a0por \u00a0el \u00a0art. 225 del C. de P.P., la misma ser\u00e1 rechazada \u00a0in \u00a0l\u00edmine, declarando, en \u00a0consecuencia, desierto el recurso. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la CORTE SUPREMA \u00a0DE JUSTICIA, en SALA DE CASACION PENAL, \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0RESUELVE: \u00a0\u00a0<\/p>\n<p>1. \u00a0RECHAZAR \u00a0IN LIMINE la demanda presentada \u00a0por el defensor del procesado MARTIN ALONSO AMAYA LEON. \u00a0\u00a0<\/p>\n<p>2. \u00a0DECLARAR \u00a0como consecuencia DESIERTO \u00a0 el \u00a0 recurso \u00a0extraordinario \u00a0interpuesto \u00a0 \u00a0ante \u00a0 \u00a0el \u00a0 Tribunal \u00a0 Superior \u00a0 del \u00a0 Distrito \u00a0 Judicial \u00a0 de \u00a0C\u00facuta. \u00a0\u00a0<\/p>\n<p>Contra \u00a0la \u00a0presente \u00a0decisi\u00f3n \u00a0no \u00a0procede \u00a0recurso alguno, de conformidad con el art. 197 del C. de P.P. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0 c\u00famplase \u00a0y \u00a0devu\u00e9lvase \u00a0el \u00a0expediente al Tribunal de or\u00edgen. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 JORGE ANIBAL GOMEZ GALLEGO \u00a0\u00a0<\/p>\n<p>FERNANDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ARBOLEDA \u00a0RIPOLL\u00a0\u00a0\u00a0\u00a0\u00a0 JORGE ENRIQUE CORDOBA POVEDA \u00a0\u00a0<\/p>\n<p>CARLOS \u00a0AUGUSTO \u00a0GALVEZ \u00a0ARGOTE\u00a0 EDGAR \u00a0LOMBANA TRUJILLO \u00a0\u00a0<\/p>\n<p>MARIO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 MANTILLA \u00a0NOUGUES\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 CARLOS \u00a0EDUARDO \u00a0MEJIA \u00a0ESCOBAR \u00a0\u00a0<\/p>\n<p>ALVARO \u00a0ORLANDO \u00a0PEREZ \u00a0PINZON\u00a0\u00a0 \u00a0NILSON PINILLA PINILLA\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0PATRICIA SALAZAR CUELLAR \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0Secretaria \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No. 15269 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0CORTE SUPREMA DE JUSTICIA \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0SALA DE CASACION PENAL \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Magistrado Ponente \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0DR. CARLOS AUGUSTO GALVEZ ARGOTE \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Aprobado Acta No.115 \u00a0\u00a0 Santaf\u00e9 de Bogot\u00e1, D.C., tres (3) de agosto \u00a0de mil novecientos noventa y nueve (1.999). \u00a0\u00a0 \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2249","post","type-post","status-publish","format-standard","hentry","category-7"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/2249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=2249"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/2249\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=2249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=2249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=2249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}