{"id":22370,"date":"2023-09-12T16:34:10","date_gmt":"2023-09-12T16:34:10","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3581510-02-11\/"},"modified":"2023-09-12T16:34:10","modified_gmt":"2023-09-12T16:34:10","slug":"3581510-02-11","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/12\/3581510-02-11\/","title":{"rendered":"35815(10-02-11)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso n.\u00ba 35815 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>JULIO ENRIQUE SOCHA SALAMANCA \u00a0<\/p>\n<p>Aprobado Acta N\u00ba 40 \u00a0<\/p>\n<p>Bogot\u00e1 D.C., diez (10) de febrero de dos mil \u00a0once (2011) \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Decide \u00a0la \u00a0Sala \u00a0acerca \u00a0de los fundamentos \u00a0l\u00f3gicos \u00a0y \u00a0de \u00a0debida argumentaci\u00f3n de la demanda de casaci\u00f3n presentada por \u00a0el \u00a0defensor de CARLOS JAVIER G\u00d3MEZ TORRES \u00a0contra \u00a0el \u00a0fallo \u00a0del \u00a0Tribunal \u00a0Superior de Distrito Judicial de \u00a0Pamplona \u00a0(N. \u00a0de \u00a0S.), que \u00a0confirm\u00f3 \u00a0parcialmente \u00a0el \u00a0emitido \u00a0en \u00a0el \u00a0Juzgado \u00a0Penal del Circuito de esa \u00a0ciudad, \u00a0mediante el cual fue condenado como autor del delito de defraudaci\u00f3n a \u00a0los derechos patrimoniales de autor. \u00a0\u00a0<\/p>\n<p>HECHOS Y ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>1. Seg\u00fan lo rese\u00f1a \u00a0la \u00a0actuaci\u00f3n, \u00a0el \u00a010 \u00a0de \u00a0abril \u00a0de \u00a02002, \u00a0ante \u00a0la \u00a0Comisi\u00f3n \u00a0Nacional \u00a0de \u00a0Televisi\u00f3n, \u00a0el \u00a0gerente \u00a0de \u00a0Parab\u00f3lica \u00a0Chinacota \u00a0Ltda., \u00a0empresa legalmente constituida y concesionaria \u00a0autorizada \u00a0del servicio p\u00fablico de televisi\u00f3n por cable, present\u00f3 ante dicha \u00a0entidad \u00a0queja \u00a0poniendo \u00a0en \u00a0conocimiento \u00a0que donde opera, igualmente funciona \u00a0desde \u00a0hace \u00a0varios \u00a0meses una empresa \u201cpirata\u201d \u00a0que \u00a0bajo \u00a0 diferentes \u00a0 nombres \u00a0 como \u00a0 \u201cMultivisi\u00f3n\u201d, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u201cTelechinacota\u201d \u00a0o \u00a0\u201cUnitel \u00a0Ltda.\u201d, \u00a0 se \u00a0dedica \u00a0a \u00a0comercializar \u00a0 \u00a0 \u00a0 \u00a0 un \u00a0 \u00a0 \u00a0 \u00a0\u201cpaquete\u201d que \u00a0incluye \u00a0la \u00a0emisi\u00f3n \u00a0de \u00a0se\u00f1ales \u00a0codificadas o encriptadas correspondientes, \u00a0entre \u00a0otros, \u00a0a \u00a0canales \u00a0como \u00a0HBO-OLE, CINE CANAL, \u00a0FOX, \u00a0etc., \u00a0cuya \u00a0difusi\u00f3n \u00a0y \u00a0aprovechamiento s\u00f3lo \u00a0puede \u00a0 \u00a0hacerse \u00a0 con \u00a0 los \u00a0 correspondientes \u00a0 permisos \u00a0 legales1. \u00a0\u00a0<\/p>\n<p>2. De la respectiva \u00a0denuncia \u00a0y \u00a0sus \u00a0anexos \u00a0la Comisi\u00f3n Nacional de Televisi\u00f3n dio traslado a la \u00a0Fiscal\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0entidad \u00a0que \u00a0tras una ingente indagaci\u00f3n \u00a0previa2, \u00a0el \u00a024 \u00a0de \u00a0octubre \u00a0de \u00a02002 \u00a0declar\u00f3 \u00a0formalmente \u00a0abierta \u00a0la \u00a0instrucci\u00f3n \u00a0y \u00a0orden\u00f3 \u00a0vincular \u00a0a la misma a CARLOS \u00a0JAVIER \u00a0 G\u00d3MEZ \u00a0 TORRES, \u00a0 representante \u00a0 legal \u00a0de \u00a0\u201cUNITEL LTDA.\u201d, \u00a0contra \u00a0quien, \u00a0una \u00a0vez \u00a0o\u00eddo \u00a0en \u00a0indagatoria, \u00a0el \u00a0instructo \u00a0profiri\u00f3 \u00a0el \u00a029 septiembre de 2004 resoluci\u00f3n de \u00a0acusaci\u00f3n \u00a0en \u00a0calidad \u00a0de \u00a0autor de las conductas punibles de defraudaci\u00f3n de \u00a0fluidos \u00a0y \u00a0defraudaci\u00f3n \u00a0a \u00a0los \u00a0derechos patrimoniales de autor, cometidos en \u00a0concurso \u00a0heterog\u00e9neo, de conformidad con los art\u00edculos 31, 256 y 71 de la Ley \u00a0599 \u00a0 de \u00a020003, \u00a0decisi\u00f3n \u00a0que \u00a0apelada por el defensor del citado fue confirmada \u00a0integralmente \u00a0 el \u00a0 10 \u00a0 de \u00a0 febrero \u00a0 de \u00a0 20064. \u00a0\u00a0<\/p>\n<p>3. La siguiente fase \u00a0procesal \u00a0se adelant\u00f3 en el Juzgado Penal del Circuito de Pamplona (N. \u00a0de \u00a0S.), etapa en la que con base en \u00a0la \u00a0impugnaci\u00f3n \u00a0formulada por la asistencia letrada del acusado a la decisi\u00f3n \u00a0del \u00a0funcionario \u00a0de \u00a0conocimiento, adoptada en la audiencia preparatoria, en el \u00a0sentido \u00a0de \u00a0no \u00a0cesar \u00a0procedimiento \u00a0respecto \u00a0del \u00a0delito de defraudaci\u00f3n de \u00a0fluidos \u00a0 por \u00a0 ausencia \u00a0 de \u00a0querella \u00a0de \u00a0parte, \u00a0el \u00a0superior \u00a0funcional \u00a0en \u00a0pronunciamiento \u00a0de \u00a09 \u00a0de \u00a0agosto de 2006, declar\u00f3 extinguida la acci\u00f3n penal \u00a0por \u00a0 \u00a0la \u00a0 \u00a0causa \u00a0 \u00a0alegada \u00a0 por \u00a0 la \u00a0 defensa5. \u00a0\u00a0<\/p>\n<p>4. \u00a0Finalizado \u00a0el \u00a0debate \u00a0inherente \u00a0al \u00a0juicio, \u00a0el \u00a0juzgador \u00a0de primer grado, el 31 de julio de \u00a02009, \u00a0dict\u00f3 \u00a0contra \u00a0el \u00a0acusado \u00a0sentencia \u00a0condenatoria \u00a0por \u00a0el \u00a0delito \u00a0de \u00a0defraudaci\u00f3n \u00a0a \u00a0los derechos patrimoniales de autor, y en tal virtud le impuso \u00a0las \u00a0 penas \u00a0 principales \u00a0 de \u00a0 dos \u00a0(2) \u00a0a\u00f1os \u00a0de \u00a0prisi\u00f3n \u00a0y \u00a0multa \u00a0en \u00a0cuant\u00eda de veinte (20) salarios m\u00ednimos mensuales legales, \u00a0as\u00ed \u00a0como la accesoria de inhabilidad para el ejercicio de derechos y funciones \u00a0p\u00fablicas, \u00a0adem\u00e1s \u00a0de la de car\u00e1cter civil consistente en pagar a la v\u00edctima \u00a0del \u00a0 \u00a0 \u00a0comportamiento \u00a0 \u00a0 \u00a0el \u00a0 \u00a0 \u00a0equivalente \u00a0 \u00a0 a \u00a0 \u00a0 cien \u00a0 \u00a0 (100) salarios m\u00ednimos mensuales legales \u00a0por \u00a0los \u00a0perjuicios \u00a0irrogados, \u00a0y \u00a0le otorg\u00f3 la suspensi\u00f3n condicional de la \u00a0ejecuci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0 \u00a0condena6. \u00a0\u00a0<\/p>\n<p>5. \u00a0Del \u00a0anterior \u00a0pronunciamiento \u00a0apel\u00f3 \u00a0el \u00a0defensor \u00a0del \u00a0condenado, y el Tribunal Superior de \u00a0Distrito \u00a0Judicial \u00a0de Pamplona (N. de S.), \u00a0mediante \u00a0el \u00a0suyo \u00a0de \u00a08 \u00a0de \u00a0septiembre \u00a0de 2010, lo confirm\u00f3, \u00a0excepto \u00a0en \u00a0cuanto \u00a0a \u00a0la \u00a0imposici\u00f3n \u00a0del \u00a0pago de perjuicios debido a que la \u00a0demanda \u00a0de \u00a0constituci\u00f3n \u00a0en \u00a0parte \u00a0civil \u00a0del afectado no se le notific\u00f3 al \u00a0procesado, \u00a0fallo \u00a0de \u00a0segunda instancia contra el cual el mismo sujeto procesal \u00a0interpuso \u00a0el \u00a0recurso \u00a0extraordinario \u00a0de casaci\u00f3n7. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>6. El actor promueve \u00a0la \u00a0impugnaci\u00f3n \u00a0por v\u00eda discrecional y como justificaci\u00f3n para ello alega la \u00a0violaci\u00f3n \u00a0 de \u00a0la \u00a0garant\u00eda \u00a0fundamental \u00a0de \u00a0presunci\u00f3n \u00a0de \u00a0inocencia \u00a0por \u00a0desconocimiento del apotegma de in dubio pro reo. \u00a0\u00a0<\/p>\n<p>Luego \u00a0de resumir el acontecer f\u00e1ctico y el \u00a0devenir \u00a0 procesal, \u00a0 como \u00a0 cargo \u00a0 principal \u00a0 y \u00a0 \u00fanico \u00a0alega \u00a0\u201cla \u00a0violaci\u00f3n \u00a0directa \u00a0de una norma \u00a0sustancial \u00a0(art. \u00a07\u00b0, \u00a0inc. \u00a02\u00b0, \u00a0ejusdem \u00a0de la Ley 600 de 2000)\u201d, \u00a0y \u00a0en aras de acreditar ese agravio \u00a0puntualiza \u00a0que \u00a0la \u00a0causal \u00a0de \u00a0casaci\u00f3n \u00a0a \u00a0la que acude es la prevista en el \u00a0art\u00edculo \u00a0 \u00a0207-1 \u00a0 \u00a0del \u00a0 \u00a0C\u00f3digo \u00a0 de \u00a0 Procedimiento \u00a0 Penal \u00a0 \u201c\u2026es \u00a0decir, \u00a0 VIOLACI\u00d3N \u00a0 INDIRECTA \u00a0DE \u00a0LA \u00a0LEY \u00a0SUSTANCIAL, \u00a0por \u00a0ERROR \u00a0DE \u00a0HECHO \u00a0\u2013 \u00a0 FALSO \u00a0 JUICIO \u00a0DE \u00a0IDENTIDAD\u201d. \u00a0\u00a0<\/p>\n<p>Sostiene, en la demostraci\u00f3n de la censura, \u00a0que \u00a0en \u00a0las sentencias de primera y segunda instancia nada se dijo acerca de lo \u00a0alegado \u00a0por \u00a0su \u00a0defendido en cuanto a que su actividad se limit\u00f3 a una simple \u00a0agencia \u00a0 \u00a0 comercial, \u00a0 \u00a0 de \u00a0 \u00a0 suerte \u00a0 \u00a0 que \u00a0 \u00a0 por \u00a0 \u00a0 la \u00a0 \u00a0 \u201causencia \u00a0de \u00a0valoraci\u00f3n\u201d \u00a0de \u00a0la indagatoria del acusado, as\u00ed \u00a0como \u00a0del \u00a0testimonio \u00a0de \u00a0Jos\u00e9 \u00a0Fernando \u00a0Grisales \u00a0Pati\u00f1o, para quien aqu\u00e9l \u00a0desempe\u00f1aba \u00a0 \u00a0la \u00a0 \u00a0aludida \u00a0 \u00a0gesti\u00f3n, \u00a0 se \u00a0 configur\u00f3 \u00a0 el \u00a0 \u201cdesconocimiento \u00a0 \u00a0 del \u00a0 \u00a0 debido \u00a0proceso\u201d \u00a0o \u00a0\u201cpor \u00a0lo \u00a0menos en criterio de la sana \u00a0critica \u00a0la tergiversaci\u00f3n en conjunto\u201d \u00a0de \u00a0aquellos \u00a0medios \u00a0demostrativos, circunstancia que igualmente, \u00a0agrega, \u00a0\u201cafect\u00f3 el deber \u00a0legal \u00a0 \u00a0 de \u00a0 \u00a0 la \u00a0 \u00a0 integralidad \u00a0 \u00a0 en \u00a0 \u00a0 la \u00a0 \u00a0investigaci\u00f3n\u201d. \u00a0\u00a0<\/p>\n<p>Precisa \u00a0que \u00a0como \u00a0con \u00a0sujeci\u00f3n \u00a0a \u00a0eses \u00a0elementos \u00a0de \u00a0persuasi\u00f3n \u00a0es evidente que su prohijado actu\u00f3 con \u201cabsoluta \u00a0 \u00a0buena \u00a0 \u00a0fe\u201d, \u00a0 es \u00a0 decir, \u00a0 con \u00a0 \u201causencia \u00a0 \u00a0de \u00a0 \u00a0dolo\u201d, \u00a0lo \u00a0que \u00a0se \u00a0extraiga de las dem\u00e1s \u00a0pruebas \u00a0 documentales, \u00a0 t\u00e9cnicas, \u00a0testimoniales, \u00a0etc., \u00a0en \u00a0las \u00a0que \u00a0est\u00e1 \u00a0soportada \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0condena \u00a0 \u00a0 \u201cpierde \u00a0 \u00a0total \u00a0 val\u00eda\u201d, \u00a0 quedando \u00a0 por \u00a0ello \u00a0\u201cnatural\u00edsticamente \u00a0 relevado \u00a0 el \u00a0casacionista \u00a0de \u00a0realizar \u00a0la \u00a0respectiva \u00a0 \u00a0cr\u00edtica\u201d \u00a0frente a cada una de aqu\u00e9llas. \u00a0\u00a0<\/p>\n<p>Con \u00a0base \u00a0en \u00a0lo anterior solicita casar el \u00a0fallo \u00a0recurrido y en su lugar proferir sentencia absolutoria en aplicaci\u00f3n del \u00a0principio universal de in dubio pro reo. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>7. \u00a0Necesario \u00a0es \u00a0recordar \u00a0que, \u00a0en \u00a0cualquier \u00a0r\u00e9gimen, \u00a0la \u00a0casaci\u00f3n \u00a0atiende \u00a0a \u00a0unos \u00a0fines \u00a0superiores \u00a0cuales son la reparaci\u00f3n de los agravios inferidos a las partes con \u00a0la \u00a0sentencia recurrida, la efectividad del derecho material y de las garant\u00edas \u00a0fundamentales \u00a0de \u00a0los \u00a0intervinientes en la actuaci\u00f3n, y la unificaci\u00f3n de la \u00a0jurisprudencia \u00a0 \u00a0(Ley \u00a0 600 \u00a0 de \u00a0 2000, \u00a0 articulo \u00a0206). \u00a0\u00a0<\/p>\n<p>Sin embargo, ello de ninguna manera significa \u00a0que \u00a0la naturaleza de este mecanismo sea de libre configuraci\u00f3n, desprovisto de \u00a0todo \u00a0rigor, y que tenga como objetivo abrir un espacio procesal semejante al de \u00a0las \u00a0instancias \u00a0para \u00a0prolongar \u00a0el \u00a0debate respecto de los puntos que han sido \u00a0materia \u00a0de \u00a0controversia, \u00a0pues \u00a0ha de resaltarse que al proponer el recurso el \u00a0censor \u00a0 debe \u00a0 sujetarse \u00a0 a \u00a0 las \u00a0causales \u00a0taxativamente \u00a0se\u00f1aladas \u00a0en \u00a0el \u00a0ordenamiento \u00a0procesal, \u00a0y \u00a0con \u00a0observancia \u00a0de \u00a0los \u00a0presupuestos de l\u00f3gica y \u00a0argumentaci\u00f3n \u00a0 inherentes \u00a0 a \u00a0cada \u00a0motivo \u00a0extraordinario \u00a0de \u00a0impugnaci\u00f3n, \u00a0persuadir \u00a0a \u00a0la \u00a0Corte \u00a0de \u00a0que \u00a0con \u00a0la \u00a0decisi\u00f3n \u00a0atacada se ha originado el \u00a0quebranto de alguna de aquellas finalidades. \u00a0\u00a0<\/p>\n<p>8. \u00a0En el presente \u00a0asunto, \u00a0inicialmente \u00a0es obligatorio precisar que de conformidad con lo normado \u00a0en \u00a0el inciso 1\u00ba del art\u00edculo 205 de la Ley 600 de 2000, estatuto vigente para \u00a0la \u00a0\u00e9poca \u00a0en que ocurrieron los hechos debatidos, el recurso extraordinario de \u00a0casaci\u00f3n \u00a0resulta \u00a0viable contra sentencias proferidas en segunda instancia por \u00a0los \u00a0tribunales \u00a0superiores de distrito judicial y por el Tribunal Penal Militar \u00a0por \u00a0delitos \u00a0que \u00a0tengan \u00a0se\u00f1alada \u00a0pena privativa de la libertad cuyo m\u00e1ximo \u00a0exceda de ocho (8) a\u00f1os. \u00a0\u00a0<\/p>\n<p>Cuando \u00a0el \u00a0fallo \u00a0de \u00a0segundo \u00a0grado \u00a0no es \u00a0emitido \u00a0por \u00a0los \u00a0aludidos despachos o el delito por el que se procede consagra \u00a0una \u00a0sanci\u00f3n privativa de la libertad de ocho a\u00f1os o \u00a0inferior, \u00a0el \u00a0inciso \u00a0tercero \u00a0del \u00a0citado \u00a0precepto \u00a0faculta \u00a0 \u00a0 a \u00a0 \u00a0 la \u00a0 \u00a0 Sala \u00a0 \u00a0 para \u00a0 \u00a0 admitir \u00a0discrecionalmente \u00a0 las \u00a0demandas \u00a0de \u00a0casaci\u00f3n \u00a0que \u00a0cumplan \u00a0 con \u00a0 los \u00a0dem\u00e1s \u00a0requisitos, \u00a0siempre \u00a0que \u00a0sea \u00a0necesario \u00a0para \u00a0el \u00a0desarrollo \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 jurisprudencia \u00a0 o \u00a0 la \u00a0 garant\u00eda \u00a0de \u00a0los \u00a0derechos \u00a0fundamentales. \u00a0\u00a0<\/p>\n<p>De tiempo atr\u00e1s tiene precisado la Corte que \u00a0una \u00a0disertaci\u00f3n con la que se aspire a persuadirla acerca de la procedencia de \u00a0la \u00a0casaci\u00f3n \u00a0discrecional, \u00a0debe \u00a0estar \u00a0dirigida a hacerle ver la necesidad de su pronunciamiento, en forma \u00a0tal \u00a0que \u00a0si \u00a0se \u00a0trata \u00a0de \u00a0reclamar la garant\u00eda de un derecho fundamental, le \u00a0corresponde \u00a0al \u00a0recurrente \u00a0se\u00f1alar \u00a0el o los que fueron desconocidos, indicar \u00a0las \u00a0normas \u00a0constitucionales \u00a0y\/o \u00a0legales que los protegen y la determinaci\u00f3n \u00a0que \u00a0debe \u00a0adoptarse \u00a0para \u00a0su \u00a0salvaguarda. \u00a0Y \u00a0si \u00a0el \u00a0motivo \u00a0invocado \u00a0es el \u00a0desarrollo \u00a0de \u00a0la \u00a0jurisprudencia, \u00a0debe \u00a0puntualizar \u00a0el \u00a0tema \u00a0jur\u00eddico \u00a0que \u00a0requiere \u00a0definici\u00f3n \u00a0o \u00a0precisi\u00f3n, \u00a0sea \u00a0porque \u00a0es \u00a0nuevo \u00a0o \u00a0porque existen \u00a0posiciones \u00a0opuestas \u00a0que \u00a0deben \u00a0ser \u00a0unificadas para la acertada soluci\u00f3n del \u00a0asunto debatido y frente a casos futuros. \u00a0\u00a0<\/p>\n<p>Como \u00a0la \u00a0conducta \u00a0punible debatida en este \u00a0proceso \u00a0 es \u00a0 la \u00a0de \u00a0defraudaci\u00f3n \u00a0a \u00a0los \u00a0derechos \u00a0patrimoniales \u00a0de \u00a0autor \u00a0(Ley \u00a0599 \u00a0de \u00a02000, art\u00edculo 271, modificado por la \u00a0Ley \u00a0 1032 \u00a0 de \u00a02006, \u00a0art\u00edculo \u00a02), \u00a0para \u00a0la \u00a0cual \u00a0en \u00a0 la \u00a0 actualidad \u00a0est\u00e1 \u00a0prevista \u00a0una \u00a0pena m\u00e1xima de prisi\u00f3n de apenas ocho \u00a0(8) \u00a0 \u00a0a\u00f1os8, \u00a0tal \u00a0guarismo \u00a0resulta \u00a0inferior \u00a0al \u00a0l\u00edmite \u00a0establecido \u00a0en el \u00a0art\u00edculo \u00a0205 \u00a0de la Ley 600 de 2000, luego el recurso extraordinario s\u00f3lo era \u00a0posible \u00a0 intentarlo \u00a0 a \u00a0 trav\u00e9s \u00a0de \u00a0la \u00a0casaci\u00f3n \u00a0excepcional, modalidad a la que ciertamente acudi\u00f3 el \u00a0demandante. \u00a0\u00a0<\/p>\n<p>Sin \u00a0embargo, pese a ese acierto formal, las \u00a0razones \u00a0ofrecidas \u00a0por el actor no llevan a la Sala a la convicci\u00f3n de que sea \u00a0perentoria \u00a0o urgente la admisi\u00f3n de la demanda con el fin de cumplir los fines \u00a0propios \u00a0de la casaci\u00f3n discrecional, pues con evidente desconocimiento de esos \u00a0objetivos, \u00a0as\u00ed \u00a0como de las exigencias que gobiernan cada una de sus causales, \u00a0el \u00a0memorialista \u00a0pide \u00a0enervar \u00a0la condena sin una propuesta seria acerca de la \u00a0ocurrencia \u00a0de \u00a0dislate \u00a0alguno \u00a0materializado \u00a0en la providencia emitida por el \u00a0Tribunal. \u00a0\u00a0<\/p>\n<p>9. \u00a0Observados los \u00a0razonamientos \u00a0consignados \u00a0en \u00a0la \u00a0demanda, es evidente que lo discutido por el \u00a0censor \u00a0es la soluci\u00f3n dada al caso con base en la apreciaci\u00f3n de las pruebas, \u00a0empero, \u00a0en \u00a0ese ejercicio de confutaci\u00f3n no logra demostrar de manera objetiva \u00a0la \u00a0incursi\u00f3n \u00a0por \u00a0parte \u00a0del \u00a0Tribunal en una motivaci\u00f3n falsa, sof\u00edstica o \u00a0aparente, \u00a0\u00fanica \u00a0posibilidad \u00a0de \u00a0atacar \u00a0por \u00a0v\u00eda discrecional una sentencia \u00a0cuando \u00a0la \u00a0discusi\u00f3n \u00a0gira \u00a0entorno \u00a0a \u00a0la \u00a0estimaci\u00f3n \u00a0probatoria, ya que de \u00a0acreditarse \u00a0un \u00a0yerro \u00a0semejante se estar\u00eda ante una inobjetable v\u00eda de hecho \u00a0por \u00a0indebida fundamentaci\u00f3n de la sentencia, vicio que la Corte estar\u00eda en el \u00a0deber \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 conjurar9. \u00a0\u00a0<\/p>\n<p>9.1. \u00a0En \u00a0efecto, \u00a0atendido \u00a0el \u00a0fundamento \u00a0inteligible \u00a0de \u00a0las \u00a0decisiones \u00a0de primero y segundo \u00a0grado, \u00a0integradas como unidad jur\u00eddica inescindible, el censor estaba obligado \u00a0a \u00a0enfrentar \u00a0por \u00a0separado \u00a0esa \u00a0doble \u00a0fundamentaci\u00f3n, y a demostrar frente a \u00a0ambas, \u00a0mediante \u00a0la \u00a0acreditaci\u00f3n \u00a0de \u00a0alguno \u00a0de \u00a0los \u00a0errores t\u00edpicos de la \u00a0violaci\u00f3n \u00a0indirecta, \u00a0que \u00a0la apreciaci\u00f3n de las pruebas ostentaba vicios por \u00a0errores \u00a0de \u00a0derecho (falsos juicios de legalidad y de \u00a0convicci\u00f3n), o hecho (falso \u00a0juicios \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0identidad, \u00a0 \u00a0 existencia \u00a0 \u00a0 o \u00a0 \u00a0 raciocinio). \u00a0\u00a0<\/p>\n<p>Si pretend\u00eda aludir a la primera modalidad, \u00a0como \u00a0en \u00a0materia penal los diferentes medios de prueba no est\u00e1n sometidos a un \u00a0sistema \u00a0tarifado, \u00a0en principio, resultaba improcedente arg\u00fcir un falso juicio \u00a0de \u00a0 convicci\u00f3n, \u00a0 luego \u00a0\u00fanicamente \u00a0cabr\u00eda \u00a0proponer \u00a0un \u00a0falso \u00a0juicio \u00a0de \u00a0legalidad, \u00a0orientado \u00a0a \u00a0demostrar \u00a0que \u00a0los \u00a0juzgadores valoraron elementos de \u00a0conocimiento \u00a0que \u00a0carec\u00edan \u00a0de \u00a0requisitos legales en su aducci\u00f3n pr\u00e1ctica o \u00a0incorporaci\u00f3n, \u00a0o \u00a0que desestimaron los que si los reun\u00edan, entendiendo que no \u00a0satisfac\u00edan esos presupuestos. \u00a0\u00a0<\/p>\n<p>Y \u00a0si \u00a0el \u00a0ataque \u00a0se \u00a0dirig\u00eda a evidenciar \u00a0yerros \u00a0de \u00a0hecho, \u00a0en \u00a0el \u00a0desarrollo argumental estaba llamado precisar si los \u00a0dislates \u00a0materializados \u00a0frente \u00a0a \u00a0cada \u00a0uno de los distintos medios de prueba \u00a0fueron \u00a0constitutivos \u00a0de falso juicio de existencia, falso juicio de identidad, \u00a0o falso raciocinio. \u00a0\u00a0<\/p>\n<p>El \u00a0falso juicio de existencia ocurre cuando \u00a0el \u00a0juez \u00a0deja \u00a0de \u00a0apreciar \u00a0el \u00a0contenido \u00a0de \u00a0un \u00a0medio \u00a0de \u00a0prueba \u00a0legal \u00a0y \u00a0oportunamente \u00a0adosado \u00a0a \u00a0la actuaci\u00f3n (falso juicio \u00a0de \u00a0 existencia \u00a0por \u00a0omisi\u00f3n), \u00a0o \u00a0hace \u00a0precisiones \u00a0f\u00e1cticas \u00a0extra\u00f1as \u00a0a \u00a0los \u00a0elementos \u00a0de prueba obrantes, o que atribuye a un \u00a0elemento \u00a0de \u00a0persuasi\u00f3n \u00a0que en verdad no reposa en el expediente (falso \u00a0 \u00a0juicio \u00a0 de \u00a0 existencia \u00a0 por \u00a0 suposici\u00f3n). \u00a0\u00a0<\/p>\n<p>Por su parte, en el falso juicio de identidad \u00a0el \u00a0juzgador, \u00a0al \u00a0aprehender \u00a0el \u00a0contenido \u00a0de \u00a0un \u00a0medio de prueba le recorta \u00a0apartes \u00a0trascendentes de su literalidad (falso juicio \u00a0de \u00a0 \u00a0identidad \u00a0 \u00a0por \u00a0 \u00a0cercenamiento), \u00a0 adiciona \u00a0circunstancias \u00a0f\u00e1cticas \u00a0ajenas \u00a0a \u00a0su \u00a0texto (falso \u00a0juicio \u00a0de \u00a0identidad \u00a0por \u00a0adici\u00f3n), \u00a0o transforma o \u00a0cambia \u00a0 el \u00a0 sentido \u00a0 fidedigno \u00a0 de \u00a0 su \u00a0 expresi\u00f3n \u00a0material \u00a0(falso \u00a0 juicio \u00a0 de \u00a0 identidad \u00a0por \u00a0tergiversaci\u00f3n), \u00a0dislates con los que le hace decir a la prueba lo que en realidad \u00a0no afirma. \u00a0\u00a0<\/p>\n<p>Por \u00a0acreditar \u00a0los \u00a0citados \u00a0vicios, \u00a0en el \u00a0primer \u00a0evento, \u00a0es \u00a0preciso indicar el lugar del proceso en el que se encuentra \u00a0adjunto \u00a0el \u00a0medio \u00a0de \u00a0prueba omitido y su contenido, o destacar la concreci\u00f3n \u00a0f\u00e1ctica \u00a0plasmada \u00a0en \u00a0el \u00a0fallo \u00a0y que carece de acreditaci\u00f3n con las pruebas \u00a0allegadas, \u00a0 o \u00a0cuya \u00a0demostraci\u00f3n \u00a0se \u00a0atribuy\u00f3 \u00a0a \u00a0una \u00a0prueba \u00a0ajena \u00a0a \u00a0la \u00a0actuaci\u00f3n; \u00a0y \u00a0en \u00a0el \u00a0segundo, \u00a0basta con hacer un ejercicio de confrontaci\u00f3n \u00a0veraz \u00a0e imparcial entre el texto o tenor del medio de prueba y la s\u00edntesis que \u00a0de \u00a0su \u00a0contenido \u00a0postul\u00f3 \u00a0el \u00a0juzgador, \u00a0en \u00a0aras de evidenciar alguno de los \u00a0dislates \u00a0atr\u00e1s \u00a0singularizados (adici\u00f3n, supresi\u00f3n \u00a0o distorsi\u00f3n). \u00a0\u00a0<\/p>\n<p>Luego de lo anterior, en uno u otro caso, es \u00a0forzoso \u00a0ilustrar \u00a0c\u00f3mo \u00a0ese \u00a0desacierto \u00a0fue \u00a0determinante \u00a0de una conclusi\u00f3n \u00a0jur\u00eddica \u00a0equivocada, \u00a0pues \u00a0la \u00a0correcci\u00f3n \u00a0de \u00a0tales desaguisados y la nueva \u00a0valoraci\u00f3n \u00a0de \u00a0esas \u00a0pruebas, \u00a0en \u00a0conjunto \u00a0y de manera racional, lleva a una \u00a0soluci\u00f3n favorable a la parte que alega tales vicios. \u00a0\u00a0<\/p>\n<p>En \u00a0el falso raciocinio, a diferencia de los \u00a0dos \u00a0anteriores \u00a0errores \u00a0de \u00a0hecho, \u00a0adem\u00e1s \u00a0de no discutir la legalidad de la \u00a0prueba, \u00a0es \u00a0forzoso \u00a0aceptar \u00a0que \u00a0est\u00e1 \u00a0adosada \u00a0al \u00a0proceso y que su texto o \u00a0contenido \u00a0f\u00e1ctico fue extractado de manera fidedigna por el fallador, toda vez \u00a0que \u00a0el yerro recae en las deducciones hechas a partir de su literalidad, cuando \u00a0las \u00a0mismas \u00a0entra\u00f1an \u00a0desconocimiento \u00a0de \u00a0los \u00a0postulados de la sana cr\u00edtica \u00a0(leyes \u00a0de \u00a0la \u00a0ciencia, \u00a0reglas \u00a0de \u00a0la \u00a0l\u00f3gica, \u00a0o \u00a0m\u00e1ximas \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0experiencia \u00a0 \u00a0y \u00a0 \u00a0el \u00a0 \u00a0sentido \u00a0 \u00a0com\u00fan). \u00a0\u00a0<\/p>\n<p>En \u00a0tales \u00a0eventos \u00a0le corresponde al censor \u00a0desarrollar \u00a0una \u00a0dial\u00e9ctica \u00a0orientada \u00a0a \u00a0ense\u00f1ar \u00a0cu\u00e1l \u00a0fue \u00a0la \u00a0ley de la \u00a0ciencia, \u00a0regla \u00a0l\u00f3gica \u00a0o \u00a0m\u00e1xima \u00a0de \u00a0la \u00a0experiencia \u00a0o \u00a0el \u00a0sentido com\u00fan \u00a0equivocadamente \u00a0empleada \u00a0por \u00a0el \u00a0funcionario, y cu\u00e1l es la que acertadamente \u00a0corresponde \u00a0utilizar, \u00a0con \u00a0el \u00a0fin \u00a0de \u00a0arribar \u00a0a \u00a0una \u00a0conclusi\u00f3n jur\u00eddica \u00a0correcta y favorable a sus intereses. \u00a0\u00a0<\/p>\n<p>9.2. \u00a0 Resulta \u00a0palmario \u00a0que \u00a0en \u00a0la \u00a0demanda \u00a0analizada \u00a0el \u00a0actor \u00a0no \u00a0consign\u00f3 un ejercicio \u00a0argumental \u00a0 semejante \u00a0al \u00a0atr\u00e1s \u00a0esbozado, \u00a0acerca \u00a0de \u00a0las \u00a0exigencias \u00a0para \u00a0acreditar \u00a0errores de hecho o de derecho; en lugar de ello el actor se limit\u00f3 a \u00a0poner \u00a0de \u00a0presente \u00a0su interesado criterio valorativo con la pretensi\u00f3n de que \u00a0prevaleciera \u00a0frente \u00a0al \u00a0sentado \u00a0en \u00a0las \u00a0instancias, fin para el que no est\u00e1 \u00a0concebido el recurso extraordinario. \u00a0\u00a0<\/p>\n<p>Las reflexiones del recurrente no permiten a \u00a0la \u00a0Corte \u00a0observar \u00a0en \u00a0la \u00a0motivaci\u00f3n del fallo atacado un error sustancial y \u00a0grave, \u00a0apto \u00a0para \u00a0su \u00a0enjuiciamiento en sede de violaci\u00f3n indirecta de la ley \u00a0sustancial, \u00a0luego, \u00a0desde \u00a0esa perspectiva, surge evidente la impertinencia del \u00a0recurso \u00a0extraordinario \u00a0por \u00a0v\u00eda \u00a0discrecional, como mecanismo instituido para \u00a0preservar \u00a0garant\u00edas \u00a0fundamentales, \u00a0ya \u00a0que, \u00a0cuando \u00a0se \u00a0trata de eventuales \u00a0discrepancias \u00a0probatorias, \u00a0la \u00a0demanda \u00a0no \u00a0tiene \u00a0ninguna \u00a0posibilidad de ser \u00a0admitida, \u00a0 \u00a0dado \u00a0 que, \u00a0 como \u00a0 constantemente \u00a0 lo \u00a0 viene \u00a0 sosteniendo \u00a0 la \u00a0Sala: \u00a0\u00a0<\/p>\n<p>\u201c\u2026los \u00a0 reparos \u00a0relacionados \u00a0con \u00a0la \u00a0apreciaci\u00f3n \u00a0de \u00a0la \u00a0prueba, \u00a0(\u2026) \u00a0 por \u00a0 cuanto \u00a0no \u00a0significan \u00a0una \u00a0afrenta directa a los derechos fundamentales del debido proceso \u00a0y \u00a0de \u00a0defensa, \u00a0pues \u00a0el \u00a0agravio \u00a0se \u00a0mediatiza \u00a0por el establecimiento de los \u00a0errores \u00a0de \u00a0juicio \u00a0en \u00a0la \u00a0estimaci\u00f3n \u00a0de las pruebas, no pueden tenerse como \u00a0sustentaci\u00f3n \u00a0v\u00e1lida \u00a0del \u00a0recurso \u00a0de \u00a0casaci\u00f3n \u00a0discrecional. Este medio de \u00a0impugnaci\u00f3n \u00a0excepcional, \u00a0s\u00f3lo \u00a0se \u00a0justifica por la urgencia de proteger los \u00a0derechos \u00a0fundamentales \u00a0conculcados, \u00a0si \u00a0el \u00a0da\u00f1o se pone en evidencia con la \u00a0sola indicaci\u00f3n descriptiva del escrito de sustentaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u201dLos \u00a0giros de \u00a0fundamentaci\u00f3n \u00a0por \u00a0la \u00a0apreciaci\u00f3n de la prueba, dada la indeterminaci\u00f3n de \u00a0los \u00a0resultados por la posibilidad de meras discrepancias valorativas, no pueden \u00a0ser \u00a0argumento \u00a0suficiente \u00a0para \u00a0reclamar una casaci\u00f3n sujeta a tan singulares \u00a0necesidades\u201d10. \u00a0\u00a0<\/p>\n<p>Y por lo tanto: \u00a0<\/p>\n<p>\u201c\u2026en \u00a0principio, \u00a0las \u00a0posibilidades reconocidas en la jurisprudencia \u00a0para \u00a0acceder \u00a0a \u00a0la \u00a0casaci\u00f3n \u00a0discrecional \u00a0no \u00a0se extienden a las hip\u00f3tesis \u00a0planteadas \u00a0en \u00a0la \u00a0demanda, es decir, a discutir la valoraci\u00f3n judicial de los \u00a0elementos \u00a0de \u00a0convicci\u00f3n, \u00a0porque \u00a0en \u00a0esa \u00a0labor \u00a0los \u00a0jueces \u00a0cuentan con la \u00a0relativa \u00a0libertad \u00a0que \u00a0se \u00a0desprende \u00a0de \u00a0la \u00a0sana \u00a0cr\u00edtica, \u00a0a no ser que se \u00a0proponga \u00a0que \u00a0sus deducciones son producto de una motivaci\u00f3n aparente, falsa o \u00a0ausente, \u00a0supuesto \u00a0que \u00a0determinar\u00eda, \u00a0en \u00a0caso de que se demuestre y aparezca \u00a0concretado, \u00a0la \u00a0consolidaci\u00f3n \u00a0de \u00a0un \u00a0quebranto \u00a0a \u00a0las garant\u00edas, en cuanto \u00a0obedecer\u00edan \u00a0 \u00a0tales \u00a0 \u00a0deducciones \u00a0 \u00a0a \u00a0 \u00a0la \u00a0 \u00a0arbitrariedad \u00a0 \u00a0\u2014ajena \u00a0a \u00a0un \u00a0estado \u00a0democr\u00e1tico \u00a0y \u00a0constitucional\u2014 y no a la \u00a0raz\u00f3n \u00a0y a la justicia\u201d11. \u00a0\u00a0<\/p>\n<p>9.3. En Conclusi\u00f3n, \u00a0el \u00a0recurrente \u00a0no demostr\u00f3, como lo exige la jurisprudencia en eventos como el \u00a0presente, \u00a0la \u00a0configuraci\u00f3n \u00a0objetiva \u00a0de \u00a0vicios \u00a0de \u00a0apreciaci\u00f3n probatoria \u00a0determinantes \u00a0de \u00a0una motivaci\u00f3n sof\u00edstica, falsa o aparente, siendo forzoso, \u00a0en \u00a0consecuencia, \u00a0reiterar \u00a0que \u00a0el \u00a0recurso de casaci\u00f3n, en cualquiera de sus \u00a0modalidades, \u00a0 es \u00a0 en \u00a0 esencia \u00a0 un \u00a0juicio \u00a0l\u00f3gico \u00a0jur\u00eddico, \u00a0de \u00a0delicada \u00a0argumentaci\u00f3n \u00a0y cr\u00edtica vinculante, que se emite acerca de la legalidad de la \u00a0sentencia, \u00a0y \u00a0no \u00a0puede \u00a0entenderse \u00a0como instancia adicional, ni como potestad \u00a0ilimitada \u00a0para \u00a0revisar \u00a0el \u00a0proceso \u00a0en su totalidad, en sus diversos aspectos \u00a0f\u00e1cticos \u00a0 y \u00a0 normativos, \u00a0 sino \u00a0 como \u00a0 fase \u00a0 extraordinaria, \u00a0 limitada \u00a0y \u00a0excepcional. \u00a0\u00a0<\/p>\n<p>Los \u00a0principios de sustentaci\u00f3n suficiente, \u00a0limitaci\u00f3n, \u00a0cr\u00edtica \u00a0vinculante, \u00a0autonom\u00eda \u00a0de las causales, coherencia, no \u00a0exclusi\u00f3n \u00a0y no contradicci\u00f3n, ha sido dicho por la Corporaci\u00f3n, en cualquier \u00a0r\u00e9gimen \u00a0 \u00a0gobiernan \u00a0 \u00a0la \u00a0 \u00a0casaci\u00f3n. \u00a0 Los \u00a0 dos \u00a0 primeros \u00a0 (sustentaci\u00f3n \u00a0suficiente \u00a0y limitaci\u00f3n), \u00a0derivan \u00a0del \u00a0car\u00e1cter \u00a0dispositivo del recurso, e implican que la demanda debe \u00a0bastarse \u00a0a \u00a0s\u00ed misma para propiciar la invalidaci\u00f3n del fallo, y que la Corte \u00a0no \u00a0 \u00a0puede \u00a0 \u00a0entrar \u00a0 \u00a0a \u00a0 \u00a0suplir \u00a0 \u00a0sus \u00a0 vac\u00edos, \u00a0 ni \u00a0 a \u00a0 corregir \u00a0 sus \u00a0deficiencias. \u00a0\u00a0<\/p>\n<p>El \u00a0de cr\u00edtica vinculante, presupone que la \u00a0alegaci\u00f3n \u00a0debe \u00a0fundarse \u00a0en las causales previstas taxativamente por la misma \u00a0normatividad, \u00a0y \u00a0que \u00a0se somete a determinados requisitos de forma y contenido, \u00a0dependiendo \u00a0de \u00a0la \u00a0causal \u00a0invocada. \u00a0Y \u00a0los \u00a0de \u00a0autonom\u00eda, \u00a0coherencia, \u00a0no \u00a0exclusi\u00f3n \u00a0 y \u00a0no \u00a0contradicci\u00f3n, \u00a0implican \u00a0que \u00a0el \u00a0discurso \u00a0debe \u00a0mantener \u00a0identidad \u00a0tem\u00e1tica, \u00a0y \u00a0ajustarse \u00a0a \u00a0los \u00a0requerimientos \u00a0b\u00e1sicos de l\u00f3gica \u00a0general y l\u00f3gica jur\u00eddica. \u00a0\u00a0<\/p>\n<p>La inobservancia de esos requerimientos, como \u00a0en \u00a0el \u00a0asunto \u00a0estudiado, \u00a0impide \u00a0la \u00a0demostraci\u00f3n \u00a0clara \u00a0y \u00a0contundente \u00a0de \u00a0cualquiera \u00a0de \u00a0los yerros previstos por el legislador como motivo enervante del \u00a0fallo, \u00a0y \u00a0veda \u00a0a la Corte el estudio de los fundamentos f\u00e1cticos o jur\u00eddicos \u00a0de \u00a0la \u00a0decisi\u00f3n atacada, pues en atenci\u00f3n al principio de limitaci\u00f3n, y dado \u00a0el \u00a0car\u00e1cter \u00a0rogado y dispositivo de la casaci\u00f3n, las deficiencias del libelo \u00a0no \u00a0pueden \u00a0ser \u00a0enmendadas, \u00a0ni asignarse otro sentido a la expresa pretensi\u00f3n \u00a0del \u00a0demandante, \u00a0la \u00a0cual \u00a0debe \u00a0tener \u00a0un \u00a0objeto \u00a0preciso, \u00a0claro, definido y \u00a0coherente, \u00a0regido \u00a0por \u00a0causales espec\u00edficas se\u00f1aladas por la ley, con cargos \u00a0que \u00a0han \u00a0de adecuarse a \u00e9stas, los cuales se resuelven en una nueva sentencia, \u00a0diversa \u00a0 en \u00a0 objeto \u00a0y \u00a0contenido \u00a0de \u00a0la \u00a0proferida \u00a0por \u00a0los \u00a0falladores \u00a0de \u00a0instancia. \u00a0\u00a0<\/p>\n<p>10. Finalmente, la \u00a0Sala \u00a0no \u00a0observa \u00a0que \u00a0con ocasi\u00f3n del tr\u00e1mite procesal o del pronunciamiento \u00a0atacado \u00a0 se \u00a0 hubiesen \u00a0vulnerado \u00a0los \u00a0derechos \u00a0fundamentales \u00a0inherentes \u00a0al \u00a0procesado \u00a0 CARLOS \u00a0JAVIER \u00a0G\u00d3MEZ \u00a0TORRES, \u00a0como \u00a0para \u00a0que \u00a0sea \u00a0necesario el ejercicio de la facultad legal \u00a0oficiosa \u00a0 \u00a0que \u00a0 \u00a0le \u00a0 \u00a0asiste \u00a0 para \u00a0 conjurar \u00a0 alg\u00fan \u00a0 atentado \u00a0 de \u00a0 esa \u00a0estirpe. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de lo expuesto, la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, \u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>NO \u00a0 ADMITIR \u00a0la \u00a0demanda de casaci\u00f3n presentada por el defensor de \u00a0CARLOS \u00a0JAVIER \u00a0G\u00d3MEZ TORRES \u00a0de acuerdo con las razones plasmadas en el presente prove\u00eddo. \u00a0\u00a0<\/p>\n<p>Contra \u00a0esta \u00a0decisi\u00f3n \u00a0no \u00a0procede recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>JAVIER ZAPATA ORTIZ \u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0FERNANDO CASTRO CABALLERO \u00a0\u00a0<\/p>\n<p>SIGIFREDO \u00a0 ESPINOSA \u00a0 P\u00c9REZ \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 ALFREDO \u00a0G\u00d3MEZ QUINTERO \u00a0\u00a0<\/p>\n<p>MAR\u00cdA \u00a0 DEL \u00a0 ROSARIO \u00a0 GONZ\u00c1LEZ \u00a0 DE \u00a0LEMOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 AUGUSTO \u00a0 \u00a0 J. \u00a0 \u00a0IB\u00c1\u00d1EZ \u00a0GUZM\u00c1N \u00a0\u00a0<\/p>\n<p>JORGE \u00a0LUIS \u00a0QUINTERO \u00a0MILAN\u00c9S \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JULIO ENRIQUE SOCHA SALAMANCA \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 \u00a0Cuaderno original # 1, folios 1-8. \u00a0\u00a0<\/p>\n<p>2 \u00a0\u00cddem, folios 12-172. \u00a0\u00a0<\/p>\n<p>3 \u00a0\u00cddem, \u00a0 folios \u00a0 173 \u00a0 y \u00a0252-255. \u00a0Cuaderno \u00a0original \u00a0# \u00a02, \u00a0folios \u00a066-70 \u00a0y \u00a0187-207. \u00a0\u00a0<\/p>\n<p>4 \u00a0Cuaderno original # 2, folios 5-19. \u00a0\u00a0<\/p>\n<p>5 \u00a0Cuaderno original # 3, folios 323-331 y 393-396. \u00a0\u00a0<\/p>\n<p>6 \u00a0\u00cddem, folios 516-549. \u00a0\u00a0<\/p>\n<p>7 \u00a0Cuaderno del Tribunal, folios 11-21 y 48-59. \u00a0\u00a0<\/p>\n<p>8 Para \u00a0la \u00a0\u00e9poca de los hechos, sin la modificaci\u00f3n de la Ley 1032 de 2006, art\u00edculo \u00a02, \u00a0la \u00a0pena \u00a0m\u00e1xima correspondiente a esa conducta punible era de apenas cinco \u00a0(5) a\u00f1os. \u00a0\u00a0<\/p>\n<p>9 Cfr. \u00a0Sentencia de 31 de marzo de 2004, radicaci\u00f3n 17738. \u00a0\u00a0<\/p>\n<p>10 Cfr. \u00a0Autos \u00a0de \u00a027 \u00a0de \u00a0marzo \u00a0de 2007 y 9 de diciembre de 2009, radicaciones 26651 y \u00a029155, respectivamente. \u00a0\u00a0<\/p>\n<p>11 \u00a0Cfr. \u00a0Autos de 7 de febrero de 2007 y 20 de febrero de 2008, radicaciones 26.493 \u00a0y 29.008, respectivamente. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso n.\u00ba 35815 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente: \u00a0 JULIO ENRIQUE SOCHA SALAMANCA \u00a0 Aprobado Acta N\u00ba 40 \u00a0 Bogot\u00e1 D.C., diez (10) de febrero de dos mil \u00a0once (2011) \u00a0\u00a0 VISTOS \u00a0 Decide \u00a0la \u00a0Sala \u00a0acerca \u00a0de los fundamentos \u00a0l\u00f3gicos \u00a0y \u00a0de \u00a0debida argumentaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-22370","post","type-post","status-publish","format-standard","hentry","category-19"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/22370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=22370"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/22370\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=22370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=22370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=22370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}