{"id":21362,"date":"2023-09-11T22:55:18","date_gmt":"2023-09-11T22:55:18","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3473917-11-10\/"},"modified":"2023-09-11T22:55:18","modified_gmt":"2023-09-11T22:55:18","slug":"3473917-11-10","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3473917-11-10\/","title":{"rendered":"34739(17-11-10)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso \u00a0 \u00a0 n.\u00ba \u00a034739 \u00a0\u00a0<\/p>\n<p>CORTE \u00a0 SUPREMA \u00a0 DE \u00a0JUSTICIA \u00a0\u00a0<\/p>\n<p>SALA \u00a0 DE \u00a0 CASACI\u00d3N \u00a0PENAL \u00a0\u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>JULIO ENRIQUE SOCHA SALAMANCA \u00a0<\/p>\n<p>Aprobado Acta N\u00ba 371. \u00a0<\/p>\n<p>Bogot\u00e1 D.C., diecisiete (17) de noviembre de \u00a0dos mil diez (2010). \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Decide \u00a0la Sala acerca de la admisi\u00f3n de la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0en \u00a0nombre de DIEGO \u00a0FERNANDO \u00a0 ATEHORT\u00daA \u00a0 P\u00c9REZ \u00a0contra \u00a0el \u00a0fallo \u00a0del \u00a0Tribunal \u00a0 \u00a0Superior \u00a0 \u00a0de \u00a0 \u00a0Distrito \u00a0 \u00a0Judicial \u00a0 \u00a0de \u00a0 \u00a0Buga \u00a0 \u00a0(Valle), \u00a0que \u00a0confirm\u00f3 \u00a0el emitido en el \u00a0Juzgado \u00a0Tercero \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0esa \u00a0ciudad, \u00a0mediante \u00a0el \u00a0cual fue \u00a0condenado como autor responsable de secuestro extorsivo. \u00a0\u00a0<\/p>\n<p>HECHOS Y S\u00cdNTESIS PROCESAL \u00a0<\/p>\n<p>1. El 24 de octubre \u00a0de \u00a0 2008, \u00a0 en \u00a0la \u00a0finca \u00a0\u201cEl \u00a0Chalet\u201d \u00a0ubicada en el corregimiento de San Luis, municipio de La Uni\u00f3n \u00a0(Valle), \u00a0seis \u00a0sujetos \u00a0con \u00a0el \u00a0rostro cubierto penetraron clandestinamente en \u00a0horas \u00a0de \u00a0la noche y, luego de intimidar a sus moradores con armas de fuego, se \u00a0llevaron \u00a0por \u00a0la \u00a0fuerza \u00a0hacia un lugar agreste a Luis Eduardo Toro Giraldo, a \u00a0quien, \u00a0en \u00a0principio, \u00a0por dejarlo en libertad le exig\u00edan trescientos millones \u00a0de \u00a0 \u00a0 \u00a0 \u00a0pesos \u00a0 \u00a0 \u00a0 \u00a0($ \u00a0 \u00a0 \u00a0 \u00a0300\u2019000.000), \u00a0suma \u00a0 \u00a0que \u00a0 \u00a0despu\u00e9s \u00a0 \u00a0redujeron \u00a0 \u00a0a \u00a0 \u00a0treinta \u00a0 \u00a0millones \u00a0 \u00a0(30\u2019000.000) \u00a0y para cuya satisfacci\u00f3n, el 26 \u00a0del \u00a0mismo \u00a0mes, \u00a0lo \u00a0liberaron, \u00a0previa \u00a0advertencia en el sentido de que al no \u00a0cumplir \u00a0con \u00a0ese \u00a0pago \u00a0atentar\u00edan \u00a0contra \u00a0\u00e9l \u00a0o \u00a0su \u00a0esposa, conforme se lo \u00a0reiteraron en posteriores llamadas telef\u00f3nicas. \u00a0\u00a0<\/p>\n<p>Con base en la informaci\u00f3n suministrada por \u00a0la \u00a0v\u00edctima \u00a0en \u00a0su \u00a0denuncia \u00a0y \u00a0la \u00a0labor investigativa de agentes del Cuerpo \u00a0T\u00e9cnico \u00a0 de \u00a0 Investigaci\u00f3n \u00a0de \u00a0la \u00a0Fiscal\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0se \u00a0estableci\u00f3 \u00a0que \u00a0en \u00a0la \u00a0aludida \u00a0retenci\u00f3n \u00a0probablemente hab\u00edan participado \u00a0Walter \u00a0Calero, \u00a0suegro \u00a0del plagiado, y DIEGO FERNANDO \u00a0ATEHORT\u00daA \u00a0 \u00a0P\u00c9REZ, \u00a0 primo \u00a0 de \u00a0 la \u00a0 esposa \u00a0 de \u00a0\u00e9ste. \u00a0\u00a0<\/p>\n<p>2. \u00a0Legalizada \u00a0la \u00a0 \u00a0captura \u00a0de \u00a0 \u00a0 los \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0indiciados \u00a0 \u00a0 \u00a0 y \u00a0 \u00a0 \u00a0realizada \u00a0la formulaci\u00f3n de imputaci\u00f3n ante un juez con funciones \u00a0de \u00a0 \u00a0 control \u00a0 \u00a0 de \u00a0 \u00a0 garant\u00edas, \u00a0 \u00a0 ATEHORT\u00daA \u00a0P\u00c9REZ \u00a0se \u00a0allan\u00f3 a los cargos, empero, este \u00faltimo \u00a0acto \u00a0fue \u00a0declarado \u00a0nulo, a petici\u00f3n de la defensa, por el Juez Primero Penal \u00a0del \u00a0Circuito Especializado de Buga (Valle), \u00a0motivo \u00a0por \u00a0el \u00a0que \u00a0el \u00a0proceso \u00a0sigui\u00f3 su curso normal con la \u00a0presentaci\u00f3n \u00a0del \u00a0escrito \u00a0de \u00a0acusaci\u00f3n, \u00a0el \u00a014 \u00a0de \u00a0abril \u00a0de 2009, por la \u00a0conducta \u00a0punible \u00a0de \u00a0secuestro \u00a0extorsivo \u00a0agravado, \u00a0de \u00a0conformidad \u00a0con los \u00a0art\u00edculos 169 y 170-4 de la Ley 599 de 2000. \u00a0\u00a0<\/p>\n<p>3. \u00a0En \u00a0el Juzgado \u00a0Tercero \u00a0 \u00a0Penal \u00a0 \u00a0del \u00a0 \u00a0Circuito \u00a0 \u00a0Especializado \u00a0 \u00a0de \u00a0 Buga \u00a0 \u2014en \u00a0raz\u00f3n del impedimento manifestado \u00a0por \u00a0 \u00a0 \u00a0el \u00a0 \u00a0 \u00a0anterior \u00a0 \u00a0 \u00a0funcionario \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0conocimiento\u2014, \u00a0se \u00a0llevo \u00a0a \u00a0cabo \u00a0la audiencia de \u00a0acusaci\u00f3n \u00a0y \u00a0tuvo lugar el debate oral, concluido el cual su titular, el 16 de \u00a0febrero \u00a0de \u00a02010, \u00a0emiti\u00f3 \u00a0sentencia \u00a0condenatoria contra el citado encausado, \u00a0desestimando \u00a0la \u00a0circunstancia \u00a0de agravaci\u00f3n respecto del delito endilgado, y \u00a0en \u00a0tal \u00a0virtud \u00a0le \u00a0impuso \u00a0las \u00a0penas \u00a0principales \u00a0de \u00a0trescientos \u00a0cincuenta \u00a0(350) \u00a0meses \u00a0de \u00a0prisi\u00f3n y \u00a0multa \u00a0 \u00a0de \u00a0 mil \u00a0 setecientos \u00a0 (1.700) \u00a0 salarios \u00a0m\u00ednimos \u00a0mensuales \u00a0legales \u00a0vigentes, \u00a0as\u00ed \u00a0como \u00a0la \u00a0accesoria \u00a0de \u00a0inhabilidad \u00a0para \u00a0el ejercicio de derechos y funciones p\u00fablicas \u00a0por \u00a0 \u00a0un \u00a0 t\u00e9rmino \u00a0 de \u00a0 quince \u00a0 (15) a\u00f1os. \u00a0\u00a0<\/p>\n<p>4. \u00a0Apelada \u00a0la \u00a0rese\u00f1ada \u00a0decisi\u00f3n \u00a0por \u00a0el \u00a0defensor \u00a0de \u00a0ATEHORT\u00daA \u00a0P\u00c9REZ, \u00a0el Tribunal Superior del Distrito Judicial de \u00a0Buga \u00a0 (Valle), \u00a0 mediante \u00a0pronunciamiento \u00a0de \u00a030 \u00a0de \u00a0abril de 2010, la confirm\u00f3 en cuanto fue objeto de \u00a0r\u00e9plica, \u00a0fallo \u00a0de \u00a0segunda \u00a0instancia \u00a0contra el que interpuso y sustent\u00f3 en \u00a0tiempo \u00a0 \u00a0el \u00a0 \u00a0recurso \u00a0 \u00a0extraordinario \u00a0 de \u00a0 casaci\u00f3n \u00a0 el \u00a0 mismo \u00a0 sujeto \u00a0procesal. \u00a0\u00a0<\/p>\n<p>DEMANDA \u00a0<\/p>\n<p>El actor invoca el numeral 2\u00b0 del art\u00edculo \u00a0181 \u00a0de la Ley 906 de 2004, como fundamento para alegar la violaci\u00f3n del debido \u00a0proceso \u00a0y del derecho de defensa, por desconocimiento de la garant\u00eda universal \u00a0de \u00a0imparcialidad, \u00a0pues \u00a0el \u00a0juez \u00a0que \u00a0tramit\u00f3 \u00a0el \u00a0juicio \u00a0debi\u00f3 declararse \u00a0impedido \u00a0para \u00a0ello, como quiera que ante ese despacho se ven\u00eda adelantando el \u00a0juzgamiento \u00a0 de \u00a0 la \u00a0otra \u00a0persona \u00a0involucrada \u00a0en \u00a0los \u00a0hechos \u00a0(Walter \u00a0 Calero), \u00a0 respecto \u00a0de \u00a0quien, \u00a0asegura \u00a0el \u00a0actor, \u00a0con los mismos elementos de prueba que luego se practicaron \u00a0en \u00a0el \u00a0caso \u00a0de \u00a0su \u00a0representado, \u00a0el \u00a0respectivo \u00a0funcionario \u00a0emiti\u00f3 \u00a0fallo \u00a0absolutorio, \u00a0quedado \u00a0as\u00ed \u00a0contaminado para valorar con ecuanimidad los medios \u00a0de conocimiento en los que sustent\u00f3 la condena de su prohijado. \u00a0\u00a0<\/p>\n<p>Asegura \u00a0 que \u00a0 por \u00a0 lo \u00a0 anterior \u00a0 es \u00a0\u201cprocedente \u00a0la \u00a0acci\u00f3n \u00a0de \u00a0revisi\u00f3n\u201d \u00a0interpuesta, dado que se soslay\u00f3 una causal de impedimento que \u00a0obstaculizaba \u00a0la \u00a0realizaci\u00f3n \u00a0de \u00a0un \u00a0juicio \u00a0imparcial, \u00a0y para remediar ese \u00a0agravio \u00a0es \u00a0necesario \u00a0decretar \u00a0la \u00a0nulidad \u00a0de \u00a0lo \u00a0actuado \u00a0por \u00a0el \u00a0juez de \u00a0conocimiento \u00a0 o \u00a0 \u201cque \u00a0se \u00a0absuelva \u00a0[a \u00a0su \u00a0defendido] de los cargos tal como \u00a0se \u00a0hiciera (sic) con el otro \u00a0coautor\u201d. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE \u00a0<\/p>\n<p>1. \u00a0De conformidad \u00a0con \u00a0lo \u00a0establecido en el art\u00edculo 181 de la Ley 906 de 2004, nuevo C\u00f3digo de \u00a0Procedimiento \u00a0Penal, \u00a0el \u00a0recurso de casaci\u00f3n es un mecanismo de control tanto \u00a0constitucional \u00a0 \u00a0 (art\u00edculo \u00a0 \u00a0235-1) \u00a0como legal que procede contra las sentencias proferidas en segunda \u00a0instancia \u00a0y \u00a0que, \u00a0de \u00a0acuerdo \u00a0con \u00a0lo se\u00f1alado en el art\u00edculo 180 del mismo \u00a0ordenamiento, \u00a0 \u00a0 \u00a0tiene \u00a0 \u00a0 \u00a0como \u00a0 \u00a0 prop\u00f3sitos \u00a0 \u00a0 alcanzar \u00a0 \u00a0 (i) \u00a0la efectividad del derecho material, \u00a0(ii) \u00a0el \u00a0respeto \u00a0de \u00a0las \u00a0garant\u00edas \u00a0 \u00a0 fundamentales, \u00a0 \u00a0 (iii) \u00a0 la \u00a0 reparaci\u00f3n \u00a0 de \u00a0 los \u00a0agravios \u00a0inferidos \u00a0y \u00a0(iv) \u00a0 \u00a0la \u00a0 \u00a0unificaci\u00f3n \u00a0 \u00a0de \u00a0 \u00a0la \u00a0jurisprudencia. \u00a0\u00a0<\/p>\n<p>Para \u00a0hacer efectivo el cumplimiento de esos \u00a0objetivos, \u00a0en \u00a0el \u00a0mencionado \u00a0r\u00e9gimen procesal se dot\u00f3 a la Sala Penal de la \u00a0Corte \u00a0Suprema \u00a0de \u00a0Justicia \u00a0de \u00a0facultades \u00a0sustanciales \u00a0al conferirle, entre \u00a0otras, \u00a0la \u00a0potestad de superar los defectos de la demanda para decidir de fondo \u00a0cuando \u00a0los \u00a0fines de la casaci\u00f3n, fundamentaci\u00f3n de los mismos, posici\u00f3n del \u00a0impugnante \u00a0dentro \u00a0del \u00a0proceso, \u00a0e \u00edndole de la discusi\u00f3n planteada, as\u00ed lo \u00a0ameriten. \u00a0\u00a0<\/p>\n<p>Lo anterior no implica, sin embargo, que este \u00a0mecanismo \u00a0sea \u00a0de \u00a0libre \u00a0configuraci\u00f3n, desprovisto de todo rigor y que tenga \u00a0como \u00a0finalidad \u00a0abrir \u00a0un \u00a0espacio procesal semejante al de las instancias para \u00a0prolongar \u00a0el \u00a0debate \u00a0respecto \u00a0de puntos que han sido materia de controversia, \u00a0pues, \u00a0por el contrario, dada su naturaleza extraordinaria, quien acude al mismo \u00a0debe \u00a0ce\u00f1irse \u00a0a determinados requerimientos sistem\u00e1ticos basados en la raz\u00f3n \u00a0y \u00a0en \u00a0la \u00a0l\u00f3gica \u00a0argumentativa, \u00a0atinentes \u00a0a \u00a0la \u00a0observancia de coherencia, \u00a0precisi\u00f3n \u00a0y claridad en el desarrollo de cada uno de los reparos efectuados, y \u00a0desarrollarlos \u00a0conforme a las causales de procedencia previstas en el art\u00edculo \u00a0181 \u00a0del \u00a0ordenamiento \u00a0procesal, \u00a0en \u00a0aras \u00a0de persuadir a esta Corporaci\u00f3n de \u00a0revisar \u00a0el fallo de segunda instancia con el fin de corregir el pronunciamiento \u00a0que se revela contrario a derecho. \u00a0\u00a0<\/p>\n<p>De \u00a0ah\u00ed que el inciso 2\u00ba del art\u00edculo 184 \u00a0de \u00a0la Ley 906 de 2004 consagre que no ser\u00e1 admitida la demanda de casaci\u00f3n si \u00a0el \u00a0actor \u00a0carece \u00a0de inter\u00e9s para acceder al recurso; el escrito es infundado, \u00a0es \u00a0decir, \u00a0si su motivaci\u00f3n no evidencia la potencial violaci\u00f3n de garant\u00edas \u00a0y, \u00a0en \u00a0t\u00e9rminos \u00a0generales, \u201ccuando de su contexto \u00a0se \u00a0advierta fundadamente que no se precisa del fallo para cumplir alguna de las \u00a0finalidades \u00a0del \u00a0recurso\u201d, lo que puede presentarse \u00a0cuando \u00a0la \u00a0Corte \u00a0observe que los aspectos reprochados no tienen una incidencia \u00a0sustancial \u00a0en \u00a0relaci\u00f3n \u00a0con \u00a0lo \u00a0decidido \u00a0en \u00a0el \u00a0caso concreto, o que puede \u00a0responder \u00a0a \u00a0los \u00a0planteamientos \u00a0del demandante sin recurrir a valoraciones de \u00a0fondo acerca de lo que ocurri\u00f3 en la actuaci\u00f3n. \u00a0\u00a0<\/p>\n<p>2. \u00a0Desde ahora la \u00a0Sala \u00a0advierte \u00a0que \u00a0en \u00a0el presente asunto la demanda no ser\u00e1 admitida, ya que \u00a0los \u00a0reparos \u00a0consignados \u00a0en \u00a0el \u00a0respectivo \u00a0escrito carecen de las exigencias \u00a0inherentes \u00a0al \u00a0motivo de impugnaci\u00f3n alegado, pues no desarrollan con seriedad \u00a0y \u00a0rigor \u00a0un \u00a0enjuiciamiento \u00a0cr\u00edtico \u00a0de \u00a0la \u00a0sentencia \u00a0en \u00a0aras acreditar el \u00a0quebranto \u00a0del \u00a0debido \u00a0proceso, adem\u00e1s que la inconformidad puesta de presente \u00a0por \u00a0el \u00a0censor puede resolverse sin acudir a un fallo de fondo para cumplir con \u00a0alguno \u00a0 de \u00a0 los \u00a0 objetivos \u00a0 superiores \u00a0 a \u00a0los \u00a0que \u00a0sirve \u00a0este \u00a0mecanismo \u00a0extraordinario de impugnaci\u00f3n. \u00a0\u00a0<\/p>\n<p>2.1. \u00a0La causal de \u00a0casaci\u00f3n \u00a0alegada \u00a0por \u00a0el \u00a0recurrente \u00a0es \u00a0la \u00a0prevista \u00a0en el numeral 2\u00b0 del \u00a0art\u00edculo \u00a0181 \u00a0de \u00a0la \u00a0Ley \u00a0906 \u00a0de \u00a02004, \u00a0precepto \u00a0en el que se consagr\u00f3 el \u00a0tradicional \u00a0 motivo \u00a0 de \u00a0 nulidad \u00a0 por \u00a0vicios \u00a0in \u00a0procedendo, \u00a0 que \u00a0 permite \u00a0 atacar \u00a0las \u00a0decisiones \u00a0producidas \u00a0en \u00a0una \u00a0actuaci\u00f3n \u00a0con desconocimiento del debido proceso o de las \u00a0formas \u00a0 \u00a0 propias \u00a0 \u00a0del \u00a0 \u00a0juicio \u00a0 \u00a0(yerro \u00a0 \u00a0de \u00a0estructura), \u00a0 o \u00a0 con \u00a0violaci\u00f3n \u00a0de \u00a0los \u00a0derechos \u00a0fundamentales \u00a0inherentes \u00a0a \u00a0las \u00a0partes \u00a0(yerro \u00a0de \u00a0garant\u00eda). \u00a0En \u00a0tal \u00a0caso, debe tenerse en cuenta que \u00a0las \u00a0 \u00a0nulidades \u00a0 \u00a0se \u00a0 \u00a0rigen, \u00a0 \u00a0entre \u00a0 \u00a0otros, \u00a0 \u00a0por \u00a0 el \u00a0 principio \u00a0 de \u00a0taxatividad1 \u00a0y \u00a0que \u00a0la denuncia, bien sea de vulneraci\u00f3n del debido proceso o \u00a0de \u00a0 garant\u00edas \u00a0 fundamentales, \u00a0 requiere \u00a0 de \u00a0 claras \u00a0 y \u00a0 precisas \u00a0pautas \u00a0demostrativas. \u00a0\u00a0<\/p>\n<p>Al abrigo de esta v\u00eda de censura es tambi\u00e9n \u00a0factible \u00a0reclamar \u00a0por \u00a0el \u00a0desconocimiento \u00a0del principio de congruencia entre \u00a0acusaci\u00f3n \u00a0y \u00a0sentencia, \u00a0seg\u00fan \u00a0el \u00a0cual \u00a0el \u00a0acusado no podr\u00e1 ser declarado \u00a0culpable \u00a0por hechos que no consten en la acusaci\u00f3n, ni por delitos por los que \u00a0no \u00a0 \u00a0 \u00a0se \u00a0 \u00a0 \u00a0ha \u00a0 \u00a0 \u00a0solicitado \u00a0 \u00a0 \u00a0condena2, \u00a0toda vez que un error de ese \u00a0cariz \u00a0no solo compromete la estructura del proceso sino que constituye un vicio \u00a0de \u00a0garant\u00eda que afecta el derecho a la defensa al sorprend\u00e9rsele al procesado \u00a0con \u00a0 imputaciones \u00a0f\u00e1cticas \u00a0y \u00a0jur\u00eddicas \u00a0que \u00a0no \u00a0tuvo \u00a0la \u00a0oportunidad \u00a0de \u00a0controvertir \u00a0por \u00a0no haber sido incluidas en el pliego de cargos, de manera que \u00a0la \u00a0incongruencia \u00a0como \u00a0garant\u00eda \u00a0y postulado estructural del proceso, implica \u00a0que \u00a0el \u00a0fallo \u00a0debe \u00a0guardar armon\u00eda: bien con lo que el imputado acepte en la \u00a0audiencia \u00a0de \u00a0formulaci\u00f3n \u00a0de \u00a0la \u00a0imputaci\u00f3n \u00a0o \u00a0a \u00a0trav\u00e9s de preacuerdos y \u00a0negociaciones \u00a0 \u00a0celebrados \u00a0 con \u00a0 la \u00a0 Fiscal\u00eda3, \u00a0 o \u00a0ya \u00a0con \u00a0las \u00a0conductas \u00a0punibles \u00a0 \u00a0 atribuidas \u00a0 \u00a0en \u00a0 \u00a0la \u00a0 \u00a0acusaci\u00f3n4, \u00a0identidad \u00a0que \u00a0debe \u00a0estar \u00a0referida \u00a0o verificarse en tres aspectos, a saber: el personal, el f\u00e1ctico y el \u00a0jur\u00eddico5. \u00a0\u00a0<\/p>\n<p>Importante \u00a0es \u00a0reiterar \u00a0que \u00a0aun cuando la \u00a0correspondiente \u00a0demanda \u00a0no \u00a0exige \u00a0formas \u00a0espec\u00edficas para la proposici\u00f3n y \u00a0sustentaci\u00f3n \u00a0de \u00a0nulidades, \u00a0tampoco \u00a0es \u00a0un \u00a0escrito \u00a0de libre factura habida \u00a0cuenta \u00a0que \u00a0no cualquier irregularidad conspira contra la vigencia del proceso, \u00a0pues \u00a0la \u00a0afectaci\u00f3n \u00a0debe \u00a0ser \u00a0esencial y estar vinculada en calidad de medio \u00a0para \u00a0socavar \u00a0alg\u00fan \u00a0derecho \u00a0fundamental \u00a0de \u00a0las partes o intervinientes, de \u00a0suerte \u00a0que, \u00a0igual \u00a0que \u00a0en \u00a0las \u00a0otras \u00a0causales, \u00a0debe \u00a0ajustarse \u00a0a \u00a0ciertos \u00a0par\u00e1metros \u00a0l\u00f3gicos \u00a0que \u00a0permitan \u00a0comprender \u00a0con \u00a0claridad y precisi\u00f3n los \u00a0motivos \u00a0de \u00a0ataque, \u00a0las irregularidades sustanciales alegadas y la manera como \u00a0se \u00a0quebranta \u00a0la \u00a0estructura \u00a0del \u00a0proceso \u00a0o \u00a0se afectan las garant\u00edas de los \u00a0sujetos procesales. \u00a0\u00a0<\/p>\n<p>Precisamente \u00a0a \u00a0asegurar \u00a0la \u00a0claridad \u00a0y \u00a0precisi\u00f3n \u00a0de \u00a0la \u00a0censura, \u00a0as\u00ed \u00a0como \u00a0el \u00a0car\u00e1cter \u00a0serio \u00a0y vinculante del \u00a0correspondiente \u00a0reproche, \u00a0apunta la observancia de los principios que orientan \u00a0la \u00a0declaraci\u00f3n de nulidades, los cuales, si bien es cierto no est\u00e1n previstos \u00a0en \u00a0una \u00a0determinada \u00a0norma \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento Penal por el que se \u00a0tramit\u00f3 \u00a0este \u00a0asunto, \u00a0tambi\u00e9n \u00a0es verdad que validamente no puede sostenerse \u00a0que \u00a0en \u00a0ese \u00a0r\u00e9gimen \u00a0una \u00a0propuesta \u00a0de \u00a0esa \u00a0naturaleza \u00a0no est\u00e9 regida por \u00a0aquellos, \u00a0como \u00a0as\u00ed ha tenido oportunidad de puntualizarlo la Sala6. \u00a0\u00a0<\/p>\n<p>Tales axiomas se concretan en los siguientes \u00a0postulados: \u00a0s\u00f3lo \u00a0es posible solicitar la nulidad por los motivos expresamente \u00a0previstos \u00a0 \u00a0 en \u00a0 \u00a0 la \u00a0 \u00a0 ley \u00a0 \u00a0 (principio \u00a0 \u00a0de \u00a0taxatividad); \u00a0quien \u00a0alega \u00a0la \u00a0configuraci\u00f3n \u00a0de un \u00a0vicio \u00a0 enervante \u00a0 debe \u00a0especificar \u00a0la \u00a0causal \u00a0que \u00a0invoca \u00a0y \u00a0se\u00f1alar \u00a0los \u00a0fundamentos \u00a0 de \u00a0 hecho \u00a0 y \u00a0de \u00a0derecho \u00a0en \u00a0los \u00a0que \u00a0se \u00a0apoya \u00a0(principio \u00a0de \u00a0acreditaci\u00f3n); \u00a0no \u00a0puede \u00a0deprecarla \u00a0en \u00a0su \u00a0beneficio \u00a0el \u00a0sujeto procesal que con su conducta haya dado \u00a0lugar \u00a0a \u00a0la \u00a0configuraci\u00f3n del yerro invalidante, salvo el caso de ausencia de \u00a0defensa \u00a0 \u00a0 \u00a0t\u00e9cnica \u00a0 \u00a0 (protecci\u00f3n); \u00a0aunque se configure la irregularidad, ella puede convalidarse con \u00a0el \u00a0consentimiento expreso o t\u00e1cito del sujeto perjudicado, a condici\u00f3n de ser \u00a0observadas \u00a0 \u00a0 \u00a0 \u00a0las \u00a0 \u00a0 \u00a0 \u00a0garant\u00edas \u00a0 \u00a0 \u00a0 \u00a0fundamentales \u00a0 \u00a0 \u00a0 \u00a0(convalidaci\u00f3n); \u00a0 \u00a0no \u00a0 \u00a0procede \u00a0 \u00a0la \u00a0invalidaci\u00f3n \u00a0cuando \u00a0el \u00a0acto \u00a0tachado \u00a0de irregular ha cumplido el prop\u00f3sito \u00a0para \u00a0el \u00a0cual \u00a0estaba \u00a0destinado, siempre que no se viole el derecho de defensa \u00a0(principio \u00a0 \u00a0 de \u00a0 \u00a0 instrumentalidad); \u00a0quien \u00a0alegue \u00a0la rescisi\u00f3n tiene la obligaci\u00f3n indeclinable de \u00a0demostrar \u00a0no s\u00f3lo la ocurrencia de la incorrecci\u00f3n denunciada, sino que \u00e9sta \u00a0afecta \u00a0de manera real y cierta las bases fundamentales del debido proceso o las \u00a0garant\u00edas \u00a0 \u00a0 constitucionales \u00a0 \u00a0 (principio \u00a0 \u00a0de \u00a0trascendencia) \u00a0y, \u00a0adem\u00e1s, \u00a0que \u00a0para \u00a0enmendar \u00a0el \u00a0agravio \u00a0no \u00a0existe \u00a0remedio \u00a0procesal \u00a0distinto \u00a0a \u00a0la \u00a0declaratoria de nulidad \u00a0(principio \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0residualidad). \u00a0\u00a0<\/p>\n<p>2.2. \u00a0Un ejercicio \u00a0argumentativo \u00a0que \u00a0se ajuste a las se\u00f1aladas exigencias no es el consignado en \u00a0el \u00a0escrito \u00a0objeto \u00a0de \u00a0an\u00e1lisis, \u00a0pues, \u00a0empezando \u00a0porque \u00a0el \u00a0recurrente ni \u00a0siquiera \u00a0precis\u00f3 \u00a0el motivo de nulidad al que acud\u00eda, limit\u00e1ndose a proponer \u00a0la \u00a0vulneraci\u00f3n \u00a0simult\u00e1nea \u00a0del \u00a0debido \u00a0proceso y el derecho de defensa, sin \u00a0atender \u00a0que \u00a0aun \u00a0cuando \u00a0\u00e9ste \u00a0se \u00a0halla \u00a0comprendido \u00a0en aqu\u00e9l en t\u00e9rminos \u00a0generales, \u00a0ambos \u00a0son \u00a0de \u00a0contenido \u00a0y naturaleza diferente, y por lo tanto es \u00a0obligaci\u00f3n \u00a0del \u00a0censor \u00a0precisar cu\u00e1l de ellos tuvo principal afectaci\u00f3n por \u00a0causa \u00a0del \u00a0desatino \u00a0advertido, \u00a0o \u00a0si \u00a0es \u00a0que \u00a0ambos \u00a0sufrieron igual y grave \u00a0menoscabo \u00a0a \u00a0consecuencia \u00a0del \u00a0mismo, \u00a0aclaraci\u00f3n \u00a0que \u00a0no \u00a0fluye \u00a0expresa \u00a0o \u00a0t\u00e1citamente en los razonamientos de la demanda. \u00a0\u00a0<\/p>\n<p>En \u00a0lo dem\u00e1s, la irregularidad plantea como \u00a0lesiva \u00a0de \u00a0las \u00a0citadas prerrogativas, se contrae a la elemental afirmaci\u00f3n de \u00a0que \u00a0en \u00a0el \u00a0presente \u00a0asunto \u00a0se viol\u00f3 el principio de imparcialidad porque el \u00a0juez \u00a0de \u00a0conocimiento \u00a0que conden\u00f3 al procesado, fue el mismo funcionario ante \u00a0quien \u00a0se \u00a0adelant\u00f3 \u00a0el \u00a0juicio \u00a0contra otro de los probables part\u00edcipes de la \u00a0conducta \u00a0delictiva, \u00a0tramite \u00a0en \u00a0el \u00a0que \u00a0se realizaron pruebas cuya pr\u00e1ctica \u00a0luego \u00a0fue \u00a0repetida \u00a0en \u00a0la \u00a0causa \u00a0seguida \u00a0contra \u00a0su \u00a0defendido, \u00a0las cuales \u00a0sustentan su condena. \u00a0\u00a0<\/p>\n<p>Sin \u00a0desconocer \u00a0que la imparcialidad de los \u00a0jueces \u00a0es \u00a0un \u00a0atributo \u00a0con el que deben estar revestidos y reconocidos \u00e9stos \u00a0para \u00a0hacer \u00a0efectivo \u00a0el \u00a0mandato \u00a0superior \u00a0de \u00a0garantizar \u00a0una recta y eficaz \u00a0impartici\u00f3n \u00a0de \u00a0justicia \u00a0(Constituci\u00f3n \u00a0Pol\u00edtica, \u00a0art\u00edculo \u00a02\u00b0), \u00a0pilar \u00a0fundante \u00a0del Estado Social y \u00a0Democr\u00e1tico \u00a0de \u00a0Derecho, \u00a0y que como tal aqu\u00e9lla es un elemento que compone o \u00a0integra \u00a0la \u00a0noci\u00f3n \u00a0amplia \u00a0de \u00a0la garant\u00eda del debido proceso, por lo que en \u00a0ciertas \u00a0y \u00a0determinadas \u00a0circunstancias \u00a0su ausencia implica la vulneraci\u00f3n de \u00a0\u00e9sta7, \u00a0impera \u00a0se\u00f1alar \u00a0que en el caso analizado no ocurri\u00f3 situaci\u00f3n \u00a0alguna \u00a0que \u00a0pueda \u00a0desencadenar \u00a0el efecto ambiguamente perseguido por el actor \u00a0(y \u00a0esto \u00a0porque \u00a0con \u00a0base \u00a0en \u00a0los mismos argumentos \u00a0subsidiariamente \u00a0 solicita \u00a0 la \u00a0 absoluci\u00f3n \u00a0 de \u00a0 su \u00a0prohijado), \u00a0toda \u00a0vez \u00a0que \u00a0el \u00a0recurrente \u00a0no \u00a0fue \u00a0veras \u00a0y \u00a0objetivo en la \u00a0recapitulaci\u00f3n \u00a0de \u00a0los \u00a0fundamentos del reproche, lo que de suyo hace inviable \u00a0la censura atendida su incorrecci\u00f3n material. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, \u00a0ante \u00a0el Juez Tercero Penal del \u00a0Circuito \u00a0Especializado \u00a0de \u00a0Buga \u00a0se \u00a0adelant\u00f3 el juzgamiento de Walter Calero \u00a0(quien \u00a0no \u00a0acept\u00f3 \u00a0cargos), \u00a0como \u00a0probable \u00a0participe \u00a0del secuestro consumado en el ciudadano Toro Giraldo, \u00a0empero, \u00a0 la \u00a0decisi\u00f3n \u00a0absolutoria \u00a0con \u00a0la \u00a0que \u00a0result\u00f3 \u00a0favorecido \u00a0aqu\u00e9l \u00a0no \u00a0se \u00a0materializ\u00f3 \u00a0en \u00a0la \u00a0respectiva \u00a0sentencia \u00a0como \u00a0fruto de la apreciaci\u00f3n de las pruebas practicadas \u00a0en \u00a0el correspondiente debate oral y p\u00fablico. Dicho de otra forma, el juzgador, \u00a0en \u00a0ese \u00a0pronunciamiento, \u00a0no plasm\u00f3 estimaci\u00f3n probatoria alguna respecto del \u00a0citado \u00a0 acusado \u00a0 y \u00a0tampoco \u00a0anticip\u00f3 \u00a0valoraciones \u00a0adversas \u00a0acerca \u00a0de \u00a0la \u00a0responsabilidad \u00a0del \u00a0aqu\u00ed \u00a0procesado, lo cual, eventualmente, si podr\u00eda dotar \u00a0de \u00a0un \u00a0sustrato f\u00e1ctico a la discusi\u00f3n acerca de la configuraci\u00f3n del motivo \u00a0impeditivo que en abstracto alega el censor. \u00a0\u00a0<\/p>\n<p>Lo \u00a0ocurrido \u00a0fue, \u00a0como \u00a0se constata con la \u00a0copia \u00a0de \u00a0la \u00a0sentencia \u00a0adjunta \u00a0a \u00a0la \u00a0actuaci\u00f3n8, \u00a0que \u00a0al finalizar el juicio, \u00a0en \u00a0los \u00a0alegatos \u00a0de \u00a0conclusi\u00f3n, \u00a0la parte acusadora, es decir, la Fiscal\u00eda, \u00a0solicit\u00f3 \u00a0absolver \u00a0al \u00a0aludido \u00a0implicado \u00a0(en lo que \u00a0obviamente \u00a0coincidi\u00f3 \u00a0la \u00a0defensa \u00a0del mismo), motivo \u00a0por \u00a0el cual el funcionario, trayendo a colaci\u00f3n un obiter dictum inserto en un \u00a0pronunciamiento \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0 Sala9, \u00a0entendi\u00f3 que ello implicaba \u00a0retiro \u00a0de \u00a0los \u00a0cargos \u00a0y \u00a0atendiendo \u00a0la garant\u00eda de congruencia, procedi\u00f3 a \u00a0emitir \u00a0el \u00a0fallo \u00a0de \u00a0rigor, \u00a0sin \u00a0entrar \u00a0a valorar el m\u00e9rito suasorio de las \u00a0pruebas \u00a0realizadas en procura de acreditar los aspectos objetivo y subjetivo de \u00a0la conducta punible sometida a su conocimiento. \u00a0\u00a0<\/p>\n<p>Ahora \u00a0 bien, \u00a0 ese \u00a0antecedente, \u00a0el \u00a0del \u00a0juzgamiento \u00a0previo \u00a0de \u00a0uno \u00a0de \u00a0los supuestos autores del plagio de marras por \u00a0parte \u00a0del \u00a0funcionario \u00a0al \u00a0que correspondi\u00f3 conocer la causa promovida contra \u00a0ATEHORT\u00daA \u00a0P\u00c9REZ \u00a0por \u00a0los \u00a0mismos \u00a0acontecimientos, \u00a0fue \u00a0alegado \u00a0oportunamente \u00a0por su asistencia letrada \u00a0como \u00a0causal \u00a0de \u00a0recusaci\u00f3n \u00a0del \u00a0juez, \u00a0controversia resuelta por el Tribunal \u00a0Superior \u00a0de \u00a0Distrito \u00a0Judicial \u00a0de \u00a0Buga, \u00a0mediante decisi\u00f3n de 28 de mayo de \u00a02009, \u00a0en \u00a0el \u00a0sentido \u00a0de \u00a0negar \u00a0la \u00a0consecuente pretensi\u00f3n de la defensa por \u00a0ausencia \u00a0de \u00a0fundamento \u00a0objetivo, pues, para entonces, la funcionaria recusada \u00a0no \u00a0hab\u00eda \u00a0emitido \u00a0manifestaci\u00f3n \u00a0expresa \u00a0acerca \u00a0de \u00a0la \u00a0valoraci\u00f3n de las \u00a0pruebas, \u00a0ni fijado su alcance demostrativo, ni avanzado su criterio respecto de \u00a0los \u00a0 hechos, \u00a0 bien \u00a0en \u00a0un \u00a0pronunciamiento \u00a0o \u00a0decisi\u00f3n \u00a0por \u00a0fuera \u00a0de \u00a0sus \u00a0facultades \u00a0y \u00a0obligaciones \u00a0funcionales \u00a0 \u00a0o \u00a0 \u00a0en \u00a0 cumplimiento \u00a0 de \u00a0 ellas10. \u00a0\u00a0<\/p>\n<p>La \u00a0din\u00e1mica aplicada para judicializar los \u00a0hechos \u00a0constitutivos \u00a0del delito de secuestro del que fue objeto el se\u00f1or Toro \u00a0Giraldo, \u00a0permite \u00a0advertir \u00a0que al a-quo le correspondi\u00f3 el juzgamiento de uno \u00a0de \u00a0los \u00a0probables intervinientes (el cual termin\u00f3 con \u00a0fallo \u00a0absolutorio \u00a0por \u00a0las \u00a0razones \u00a0ya \u00a0anotadas), y \u00a0cuando \u00a0adelantaba ese proceso, a ra\u00edz del impedimento aceptado al Juez Primero \u00a0Penal \u00a0del \u00a0Circuito \u00a0Especializado \u00a0de \u00a0Buga \u00a0que \u00a0anul\u00f3 \u00a0el allanamiento a la \u00a0imputaci\u00f3n \u00a0del \u00a0aqu\u00ed \u00a0sentenciado, le concerni\u00f3 tramitar el juicio de \u00e9ste, \u00a0actuaciones \u00a0que \u00a0en \u00a0manera \u00a0alguna implican, per se, agravio o desconocimiento \u00a0del \u00a0principio \u00a0de \u00a0imparcialidad, \u00a0tal y como ya fue objeto de an\u00e1lisis por el \u00a0juez \u00a0natural \u00a0de \u00a0ese \u00a0aspecto, y como en casos similares lo ha puntualizado la \u00a0Corporaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Es \u00a0que \u00a0cuando \u00a0se trata de varias personas \u00a0comprometidas \u00a0en una determinada conducta punible, las cuales resultan juzgadas \u00a0de \u00a0manera \u00a0sucesiva \u00a0por \u00a0un \u00a0juez, \u00a0bien \u00a0porque unos aceptan o preacuerdan su \u00a0responsabilidad \u00a0y otros no, o ya porque su vinculaci\u00f3n al asunto se produce en \u00a0momentos \u00a0diferentes, \u00a0un cuestionamiento encaminado a acreditar la vulneraci\u00f3n \u00a0del \u00a0principio \u00a0de imparcialidad con repercusi\u00f3n en el debido proceso y\/o en el \u00a0derecho \u00a0de \u00a0defensa \u00a0en relaci\u00f3n con quienes son juzgados en forma posterior a \u00a0otros, \u00a0tiene \u00a0que \u00a0estar \u00a0afianzada \u00a0no solo en la acreditaci\u00f3n de los juicios \u00a0sucesivos \u00a0en \u00a0cabeza \u00a0del \u00a0mismo juez, sino tambi\u00e9n en la demostraci\u00f3n real y \u00a0objetiva \u00a0de \u00a0que \u00a0el funcionario en los debates procesales anteriores anticip\u00f3 \u00a0valoraciones \u00a0 \u00a0adversas \u00a0 respecto \u00a0 de \u00a0 quienes \u00a0 a \u00a0 futuro \u00a0 podr\u00edan \u00a0 ser \u00a0responsabilizados en la conducta punible. \u00a0\u00a0<\/p>\n<p>En \u00a0estos t\u00e9rminos lo advirti\u00f3 la Corte en \u00a0un \u00a0caso \u00a0en \u00a0el \u00a0que, \u00a0bajo \u00a0el imperio de la Ley 906 de 2004, se dilucidaba el \u00a0impedimento \u00a0manifestado por unos funcionarios de segunda instancia para conocer \u00a0de \u00a0la \u00a0apelaci\u00f3n \u00a0de \u00a0un \u00a0fallo respecto de unos hechos en los que en anterior \u00a0oportunidad \u00a0y \u00a0frente \u00a0a \u00a0otros \u00a0procesados \u00a0ya \u00a0hab\u00edan \u00a0emitido \u00a0sentencia en \u00a0cumplimiento de sus funciones: \u00a0\u00a0<\/p>\n<p>\u201c[Es] verdad que \u00a0de \u00a0manera \u00a0excepcional la Corte ha aceptado, que si el servidor judicial, en el \u00a0desempe\u00f1o \u00a0de \u00a0sus \u00a0funciones, anticipa conceptos acerca aspectos puntuales del \u00a0asunto, \u00a0por \u00a0fuera \u00a0de \u00a0los \u00a0marcos \u00a0propios de su competencia, o con exceso de \u00a0ellas, \u00a0que \u00a0comprometen \u00a0su criterio, como cuando ordena copias para investigar \u00a0penalmente \u00a0una \u00a0determinada \u00a0conducta y en la motivaci\u00f3n hace pronunciamientos \u00a0concretos \u00a0acerca \u00a0de \u00a0la \u00a0calificaci\u00f3n \u00a0jur\u00eddica \u00a0o \u00a0el \u00a0compromiso penal del \u00a0implicado, \u00a0resulta sensato y razonable declarar su separaci\u00f3n del conocimiento \u00a0del \u00a0asunto, \u00a0con \u00a0el \u00a0fin \u00a0de \u00a0garantizar \u00a0el \u00a0principio de imparcialidad en su \u00a0definici\u00f3n, \u00a0y evitar que se genere desconfianza en los sujetos procesales y en \u00a0la \u00a0 \u00a0 \u00a0 \u00a0 comunidad \u00a0 \u00a0 \u00a0 \u00a0en \u00a0 \u00a0 \u00a0 \u00a0general11. \u00a0\u00a0<\/p>\n<p>\u201dEn \u00a0esas \u00a0y en \u00a0otras \u00a0hip\u00f3tesis \u00a0que pueden ocasionalmente encajar en la causal de impedimento \u00a0estudiada, \u00a0lo \u00a0que \u00a0obliga \u00a0a aceptar la circunstancia de inhibici\u00f3n es que el \u00a0funcionario \u00a0haya \u00a0incurrido \u00a0con ocasi\u00f3n de sus funciones, en pronunciamientos \u00a0anticipados \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 acerca \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0aspectos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sustanciales \u00a0que \u00a0no \u00a0est\u00e9n vinculados \u00a0con \u00a0lo \u00a0que \u00a0es \u00a0objeto \u00a0de \u00a0su \u00a0conocimiento, \u00a0y \u00a0que, \u00a0por tanto, constituyen \u00a0aut\u00e9nticos \u00a0actos de prejuzgamiento, que implican compromiso indiscutible de su \u00a0criterio \u00a0 \u00a0y \u00a0 \u00a0compromete \u00a0 su \u00a0 imparcialidad \u00a0 para \u00a0 resolver \u00a0 el \u00a0 asunto \u00a0futuro. \u00a0\u00a0<\/p>\n<p>\u201dLo sustancial, \u00a0ha \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dicho \u00a0 \u00a0 \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Sala12, \u00a0es \u00a0lo \u00a0esencial \u00a0y \u00a0m\u00e1s \u00a0importante \u00a0de una cosa; en asuntos jur\u00eddicos, se identifica con el fondo de la \u00a0pretensi\u00f3n \u00a0o de la relaci\u00f3n jur\u00eddico material que se debate. Se entiende que \u00a0la \u00a0opini\u00f3n \u00a0es \u00a0vinculante cuando el funcionario judicial que la emiti\u00f3 queda \u00a0unido, \u00a0atado \u00a0o \u00a0sujeto \u00a0a \u00a0ella, \u00a0de modo que en adelante no puede ignorarla o \u00a0modificarla \u00a0 \u00a0 \u00a0 \u00a0sin \u00a0 \u00a0 \u00a0 incurrir \u00a0 \u00a0 \u00a0 en \u00a0 \u00a0 \u00a0 contradicci\u00f3n.\u201d13 \u00a0\u00a0<\/p>\n<p>Con posterioridad14, \u00a0en fallo oficioso adoptado \u00a0dentro \u00a0de \u00a0la \u00a0misma \u00a0sistem\u00e1tica procesal se reiter\u00f3 el anterior concepto al \u00a0puntualizar: \u00a0\u00a0<\/p>\n<p>\u201c[El] \u00a0deber de \u00a0imparcialidad \u00a0est\u00e1 \u00a0\u00edntimamente ligado con los institutos de los impedimentos \u00a0y \u00a0las recusaciones. Por ello se reprocha la actuaci\u00f3n del funcionario judicial \u00a0cuando \u00a0aun \u00a0a \u00a0pesar \u00a0de \u00a0encontrarse \u00a0inmerso \u00a0en causal de impedimento, no lo \u00a0declara, \u00a0o no admite una recusaci\u00f3n debidamente fundada. En ese orden, el juez \u00a0que \u00a0est\u00e9 resolviendo sobre un determinado caso debe acercarse a su resoluci\u00f3n \u00a0sin \u00a0estar \u00a0condicionado por apreciaciones precedentes a ra\u00edz de su relaci\u00f3n o \u00a0contacto \u00a0previo \u00a0con \u00a0el \u00a0objeto \u00a0del \u00a0proceso. \u00a0De manera que si en pret\u00e9rita \u00a0oportunidad \u00a0ha \u00a0evaluado \u00a0y \u00a0emitido \u00a0pronunciamiento \u00a0sobre \u00a0el \u00a0fondo \u00a0de \u00a0un \u00a0determinado \u00a0asunto \u00a0que \u00a0implique identidad de situaci\u00f3n f\u00e1ctica y partes, le \u00a0est\u00e1 \u00a0vedado \u00a0conocer \u00a0posteriormente \u00a0sobre \u00a0el \u00a0mismo, so pena de lesionar el \u00a0principio de imparcialidad. \u00a0\u00a0<\/p>\n<p>\u201dLa neutralidad y \u00a0ecuanimidad \u00a0que \u00a0deben \u00a0regir sus actuaciones puede quebrarse tanto por motivos \u00a0subjetivos \u00a0como \u00a0por motivos subjetivos. Los primeros que nacen de la relaci\u00f3n \u00a0que \u00a0tiene \u00a0con \u00a0las \u00a0partes del proceso, y los segundos que surgen del contacto \u00a0con \u00a0el \u00a0objeto \u00a0del \u00a0proceso. \u00a0Pero \u00a0no \u00a0cualquier \u00a0contacto \u00a0con la situaci\u00f3n \u00a0f\u00e1ctica \u00a0o \u00a0jur\u00eddica conduce a comprometer su objetividad. Una interpretaci\u00f3n \u00a0de \u00a0esa \u00a0naturaleza \u00a0entorpecer\u00eda \u00a0la \u00a0labor \u00a0de \u00a0administraci\u00f3n de justicia y \u00a0terminar\u00eda \u00a0por \u00a0aniquilar \u00a0la intervenci\u00f3n judicial. Es preciso constatar que \u00a0en \u00a0efecto \u00a0el \u00a0funcionario \u00a0ha prefijado conceptos en torno al fondo del asunto \u00a0que \u00a0examina \u00a0o \u00a0ha \u00a0proferido \u00a0decisiones \u00a0sustanciales \u00a0sobre el mismo, que le \u00a0impidan resolverlo o revisarlo con transparencia. \u00a0\u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>\u201dLa \u00a0 sola \u00a0intervenci\u00f3n \u00a0del \u00a0juez \u00a0dentro \u00a0de \u00a0otro \u00a0proceso, as\u00ed verse sobre los mismos \u00a0hechos, \u00a0no \u00a0puede \u00a0comprometer \u00a0en todos los casos su imparcialidad15. \u00a0 Cada \u00a0asunto \u00a0debe \u00a0analizarse \u00a0de \u00a0manera \u00a0individual y concienzuda, considerando sus \u00a0particularidades propias.\u201d \u00a0\u00a0<\/p>\n<p>Y \u00a0en cuanto al precedente judicial que cita \u00a0el \u00a0 actor16, tambi\u00e9n la Sala ya hab\u00eda aclarado lo siguiente: \u00a0\u00a0<\/p>\n<p>\u201cEs equivocado \u00a0entender \u00a0 \u00a0 \u2018como \u00a0regla\u2019 \u00a0 \u00a0que \u00a0 \u00a0la \u00a0imparcialidad \u00a0del \u00a0juez \u00a0est\u00e1 en entredicho siempre que tramita un proceso con \u00a0m\u00faltiples \u00a0vinculados \u00a0y \u00a0en \u00a0el desarrollo del mismo unos optan por preacordar \u00a0los \u00a0t\u00e9rminos \u00a0de la imputaci\u00f3n y otros no. La motivaci\u00f3n de la sentencia del \u00a0radicado \u00a0n\u00famero \u00a025407 \u00a0del 21\/03\/2007 de ninguna manera se puede convertir en \u00a0instrumento \u00a0para \u00a0suponer causales de impedimento o de recusaci\u00f3n donde no las \u00a0hay, ni para dilatar procesos penales injustificadamente. \u00a0\u00a0<\/p>\n<p>\u201dLa \u00a0regla del \u00a0pensamiento \u00a0es \u00a0la \u00a0habilitaci\u00f3n \u00a0de los jueces de la Rep\u00fablica y consiste en \u00a0que \u00a0no \u00a0se \u00a0puede \u00a0poner \u00a0en entredicho (por s\u00ed) la \u00a0imparcialidad \u00a0del \u00a0juez \u00a0que \u00a0tramita un proceso penal con m\u00faltiples imputados \u00a0cuando \u00a0en \u00a0el \u00a0curso \u00a0de \u00a0proceso hay preacuerdos; no \u00a0siempre \u00a0que \u00a0un \u00a0juez \u00a0declara \u00a0su \u00a0validez \u00a0y \u00a0condena \u00a0en \u00a0el \u00a0tr\u00e1mite de un \u00a0preacuerdo \u00a0o allanamiento se afecta la imparcialidad (Suya) en relaci\u00f3n con el \u00a0juzgamiento de los copart\u00edcipes no allanados. \u00a0\u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>\u201dEs por ello por \u00a0lo \u00a0que, \u00a0cuando \u00a0el \u00a0impugnante \u00a0alega \u00a0la nulidad por esta causa no s\u00f3lo debe \u00a0comprobar \u00a0objetivamente el \u00a0juzgamiento \u00a0sucesivo \u00a0de \u00a0los \u00a0part\u00edcipes, \u00a0sino \u00a0adem\u00e1s, \u00a0deber\u00e1 \u00a0demostrar \u00a0de \u00a0qu\u00e9 \u00a0manera \u00a0se \u00a0comprometi\u00f3 la garant\u00eda de la \u00a0imparcialidad \u00a0 del \u00a0 juez, \u00a0 y \u00a0 tal \u00a0circunstancia \u00a0particular \u00a0 \u00a0 se \u00a0 \u00a0 evidencia \u00a0 \u00a0 \u2018en \u00a0 cada \u00a0caso \u00a0concreto\u201917. Por manera \u00a0que \u00a0el \u00a0fundamento \u00a0de \u00a0la \u00a0impugnaci\u00f3n, \u00a0adem\u00e1s \u00a0de \u00a0lo objetivo (prueba del \u00a0juzgamiento \u00a0sucesivo), \u00a0tiene \u00a0que \u00a0circunscribirse \u00a0a \u00a0demostrar \u00a0cu\u00e1l era la \u00a0informaci\u00f3n \u00a0interiorizada \u00a0(elementos \u00a0probatorios y evidencias) que ten\u00eda el \u00a0juez \u00a0cuando \u00a0\u2018lleg\u00f3 a la \u00a0audiencia \u00a0de \u00a0juicio \u00a0oral \u00a0y p\u00fablico\u2019 \u00a0que \u00a0le \u00a0permitiera \u00a0estructurar \u00a0la \u00a0responsabilidad \u00a0penal \u00a0del \u00a0procesado que no preacord\u00f3. \u00a0\u00a0<\/p>\n<p>\u201dEl compromiso \u00a0de \u00a0 la \u00a0imparcialidad \u00a0del \u00a0juez \u00a0y \u00a0\u2013por \u00a0consiguiente- la afectaci\u00f3n del derecho de defensa como causa \u00a0de \u00a0nulidad \u00a0del \u00a0proceso \u00a0se \u00a0demuestra cuando el actor prueba que \u2018\u2026la \u00a0informaci\u00f3n con que cont\u00f3 el \u00a0funcionario \u00a0ex \u00a0ante \u00a0le \u00a0permiti\u00f3 \u00a0interiorizar, \u00a0preconcebir, \u00a0predefinir un \u00a0concepto \u00a0de \u00a0responsabilidad \u00a0penal \u00a0de quien, siendo part\u00edcipe de la conducta \u00a0punible \u00a0 \u00a0no \u00a0 exterioriz\u00f3 \u00a0 su \u00a0 culpa \u00a0 de \u00a0 forma \u00a0 consensuada\u2019, \u00a0es \u00a0decir, cuando el juez arriba a \u00a0la \u00a0 \u00a0 \u00a0audiencia \u00a0 \u00a0 p\u00fablica \u00a0 \u00a0 \u2018\u2026con \u00a0referentes \u00a0probatorios \u00a0concretos \u00a0y \u00a0certeros\u2019 \u00a0que \u00a0comprometan la garant\u00eda de la \u00a0imparcialidad con la que sentenciar\u00e1 a los no allanados. \u00a0\u00a0<\/p>\n<p>\u201d \u2018\u2026la \u00a0incompatibilidad entre las dos \u00a0funciones \u00a0de \u00a0juzgamiento \u00a0sucesivas \u00a0en \u00a0cabeza del mismo funcionario tiene su \u00a0n\u00facleo \u00a0 \u00a0 en \u00a0 \u00a0la \u00a0apreciaci\u00f3n \u00a0de \u00a0las \u00a0pruebas \u00a0que \u00a0comprometen \u00a0la \u00a0responsabilidad \u00a0penal \u00a0tanto \u00a0de los aceptantes, como \u00a0de \u00a0quien \u00a0opt\u00f3 \u00a0por \u00a0someterse \u00a0al \u00a0tr\u00e1mite ordinario del proceso\u201d. \u00a0(Destaca \u00a0la \u00a0Sala)\u2019\u201d \u00a0 \u00a018. \u00a0\u00a0<\/p>\n<p>3. En conclusi\u00f3n, \u00a0en \u00a0la \u00a0demanda \u00a0estudiada \u00a0el \u00a0actor no demostr\u00f3, conforme a las exigencias de \u00a0l\u00f3gica \u00a0y \u00a0argumentaci\u00f3n, \u00a0dispuestas \u00a0en \u00a0la \u00a0ley \u00a0y en la jurisprudencia, la \u00a0ocurrencia \u00a0objetiva de vicio alguno que deje sin efecto la doble presunci\u00f3n de \u00a0acierto \u00a0y legalidad con la que llega ungida a esta sede la sentencia de segunda \u00a0instancia, \u00a0 y \u00a0 que \u00a0\u00fanicamente \u00a0puede \u00a0ser \u00a0resquebrajada \u00a0en \u00a0virtud \u00a0de \u00a0la \u00a0acreditaci\u00f3n \u00a0de \u00a0yerros \u00a0manifiestos \u00a0y \u00a0graves, con trascendencia en la parte \u00a0dispositiva. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo tanto, como los argumentos ofrecidos \u00a0por \u00a0censor \u00a0no \u00a0se \u00a0sujetan a los requerimientos impuestos por el art\u00edculo 183 \u00a0del \u00a0 C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal \u00a0(Ley \u00a0906 \u00a0de \u00a02004) como condiciones insoslayables en la confecci\u00f3n \u00a0del \u00a0 libelo \u00a0 casacional, \u00a0la \u00a0Sala \u00a0no \u00a0admitir\u00e1 \u00a0la \u00a0respectiva \u00a0demanda \u00a0de \u00a0conformidad \u00a0con \u00a0lo dispuesto en el art\u00edculo 184 de la Ley 906 de 2004, por la \u00a0manifiesta \u00a0carencia \u00a0de fundamento del reproche, adem\u00e1s que no observa que con \u00a0ocasi\u00f3n \u00a0del \u00a0tr\u00e1mite \u00a0procesal \u00a0o \u00a0en \u00a0el fallo impugnado se haya configurado \u00a0violaci\u00f3n \u00a0 \u00a0de \u00a0 derechos \u00a0 o \u00a0 garant\u00edas \u00a0 fundamentales \u00a0 de \u00a0 DIEGO \u00a0FERNANDO \u00a0ATEHORT\u00daA \u00a0P\u00c9REZ, \u00a0como \u00a0para \u00a0que \u00a0sea \u00a0necesario \u00a0el \u00a0ejercicio \u00a0de \u00a0la \u00a0facultad legal oficiosa que le \u00a0asiste, a fin de asegurar su protecci\u00f3n. \u00a0\u00a0<\/p>\n<p>4. Dado que respecto \u00a0de \u00a0la \u00a0decisi\u00f3n \u00a0de inadmisi\u00f3n procede el mecanismo de insistencia de acuerdo \u00a0con \u00a0lo \u00a0establecido en el art\u00edculo 184, inciso segundo, de la Ley 906 de 2004, \u00a0es \u00a0necesario precisar que como all\u00ed no se regula su tr\u00e1mite, de tiempo atr\u00e1s \u00a0la \u00a0Sala \u00a0clarific\u00f3 \u00a0su \u00a0naturaleza \u00a0y \u00a0defini\u00f3 \u00a0las \u00a0reglas \u00a0que \u00a0habr\u00e1n \u00a0de \u00a0observarse para su aplicaci\u00f3n, en los siguientes t\u00e9rminos: \u00a0\u00a0<\/p>\n<p>a. La insistencia es \u00a0un \u00a0mecanismo \u00a0especial, que s\u00f3lo puede ser promovido por el demandante, dentro \u00a0de \u00a0los cinco (5) d\u00edas siguientes a la notificaci\u00f3n de la providencia mediante \u00a0la cual la Corte decide rechazar la demanda de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>b. La solicitud de \u00a0insistencia \u00a0puede \u00a0elevarse \u00a0ante \u00a0el \u00a0Ministerio \u00a0P\u00fablico \u00a0a \u00a0trav\u00e9s \u00a0de sus \u00a0Delegados \u00a0para \u00a0la \u00a0Casaci\u00f3n \u00a0Penal, \u00a0ante \u00a0uno \u00a0de \u00a0los Magistrados que hayan \u00a0salvado \u00a0voto \u00a0en \u00a0cuanto \u00a0a \u00a0la decisi\u00f3n mayoritaria de inadmitir la demanda o \u00a0ante \u00a0uno \u00a0de \u00a0los Magistrados que no intervino en la discusi\u00f3n y no suscribi\u00f3 \u00a0el correspondiente auto. \u00a0\u00a0<\/p>\n<p>c. \u00a0Es facultativo \u00a0del \u00a0Magistrado \u00a0disidente, \u00a0del que no particip\u00f3 en los debates o del Delegado \u00a0del \u00a0Ministerio P\u00fablico ante quien se formula la insistencia, optar por someter \u00a0el \u00a0asunto \u00a0a \u00a0consideraci\u00f3n \u00a0de \u00a0la \u00a0Sala \u00a0o no presentarlo para su revisi\u00f3n, \u00a0evento \u00a0\u00faltimo \u00a0en que informar\u00e1 de ello al peticionario en un plazo de quince \u00a0(15) d\u00edas, y \u00a0\u00a0<\/p>\n<p>d. El auto a trav\u00e9s \u00a0del \u00a0cual no se acepta la demanda de casaci\u00f3n trae como consecuencia la firmeza \u00a0de \u00a0la \u00a0sentencia \u00a0de segunda instancia contra la cual se formul\u00f3 el recurso de \u00a0casaci\u00f3n, \u00a0salvo que la insistencia prospere y lleve a la admisi\u00f3n del libelo, \u00a0o \u00a0que \u00a0sea \u00a0necesario \u00a0proveer \u00a0de \u00a0oficio \u00a0el \u00a0restablecimiento \u00a0de garant\u00edas \u00a0fundamentales de las partes o intervinientes. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de lo expuesto, la CORTE SUPREMA DE JUSTICIA, SALA DE CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>1. \u00a0NO \u00a0 ADMITIR \u00a0 la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0interpuesta \u00a0 por \u00a0 el \u00a0 defensor \u00a0de \u00a0DIEGO \u00a0FERNANDO \u00a0ATEHORT\u00daA \u00a0 P\u00c9REZ, \u00a0 de \u00a0 acuerdo \u00a0 con \u00a0lo \u00a0atr\u00e1s \u00a0puntualizado. \u00a0\u00a0<\/p>\n<p>2. \u00a0 Seg\u00fan \u00a0lo \u00a0dispuesto \u00a0en el art\u00edculo 184 de la Ley 906 de 2004, es facultad del recurrente \u00a0elevar \u00a0 petici\u00f3n \u00a0 de \u00a0 insistencia \u00a0 en \u00a0los \u00a0t\u00e9rminos \u00a0precisados \u00a0en \u00a0esta \u00a0decisi\u00f3n. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese \u00a0 y \u00a0 c\u00famplase. \u00a0\u00a0<\/p>\n<p>MAR\u00cdA \u00a0 DEL \u00a0 ROSARIO \u00a0 GONZ\u00c1LEZ \u00a0 DE \u00a0LEMOS \u00a0\u00a0<\/p>\n<p>Comisi\u00f3n de servicio \u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0SIGIFREDO ESPINOSA P\u00c9REZ \u00a0\u00a0<\/p>\n<p>Permiso \u00a0<\/p>\n<p>ALFREDO \u00a0 G\u00d3MEZ \u00a0 QUINTERO \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 AUGUSTO \u00a0 J. \u00a0IB\u00c1\u00d1EZ \u00a0GUZM\u00c1N \u00a0\u00a0<\/p>\n<p>Permiso \u00a0<\/p>\n<p>JORGE \u00a0LUIS \u00a0QUINTERO \u00a0MILAN\u00c9S \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0JULIO \u00a0ENRIQUE SOCHA SALAMANCA \u00a0\u00a0<\/p>\n<p>JAVIER ZAPATA ORTIZ \u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 Tal \u00a0axioma \u00a0est\u00e1 contemplado en la Ley 906 de 2004, art\u00edculo 458. Y de acuerdo con \u00a0la \u00a0misma normatividad las circunstancias enervantes son: la nulidad derivada de \u00a0la \u00a0prueba \u00a0il\u00edcita \u00a0y \u00a0cl\u00e1usula \u00a0de \u00a0exclusi\u00f3n (art\u00edculos 23 y 455 ib.); la \u00a0nulidad \u00a0por \u00a0incompetencia \u00a0del \u00a0juez \u00a0(art\u00edculo \u00a0456 \u00a0ib); \u00a0y \u00a0la nulidad por \u00a0violaci\u00f3n \u00a0a \u00a0garant\u00edas \u00a0fundamentales: derecho a la defensa y debido proceso, \u00a0en aspectos sustanciales (art\u00edculo 457 ib.). \u00a0\u00a0<\/p>\n<p>2 Ley \u00a0906, art\u00edculo 448. \u00a0\u00a0<\/p>\n<p>3 \u00a0Ib\u00eddem, art\u00edculos 293 y 348 a 354. \u00a0\u00a0<\/p>\n<p>4 \u00a0Ib\u00eddem, art\u00edculo 337. \u00a0\u00a0<\/p>\n<p>5 Auto \u00a0de 24 de noviembre de 2005, radicaci\u00f3n N\u00ba 24323. \u00a0\u00a0<\/p>\n<p>6 Cfr. \u00a0Entre \u00a0otras, \u00a0sentencias \u00a0de \u00a018 \u00a0de \u00a0noviembre \u00a0de 2008 y 18 de marzo de 2009, \u00a0radicaciones N\u00ba 30539 y 30710, respectivamente. \u00a0\u00a0<\/p>\n<p>7 Cfr. \u00a0Sentencia de 4 de febrero de 2009, radicaci\u00f3n N\u00ba 29415. \u00a0\u00a0<\/p>\n<p>8 \u00a0Cuaderno principal, folios 248-255. \u00a0\u00a0<\/p>\n<p>9 Cfr. \u00a0Sentencia de 13 de julio de 2006, radicaci\u00f3n N\u00ba 15843. \u00a0\u00a0<\/p>\n<p>10 \u00a0Cuaderno principal, folios 34-36. \u00a0\u00a0<\/p>\n<p>11 Cf. \u00a0Auto de 29 de noviembre de 2000, radicaci\u00f3n N\u00ba 17843. \u00a0\u00a0<\/p>\n<p>12 \u00a0Auto de 13 de julio de 2005. radicaci\u00f3n N\u00ba 23840. \u00a0\u00a0<\/p>\n<p>13 \u00a0Auto de 7 de marzo de 2007, radicaci\u00f3n N\u00ba 26853. \u00a0\u00a0<\/p>\n<p>14 \u00a0Cfr. Sentencia de 18 de junio de 2008, radicaci\u00f3n N\u00ba 29252. \u00a0\u00a0<\/p>\n<p>15 Ver \u00a0auto del 7 de marzo de 2007 (radicado 26.853). \u00a0\u00a0<\/p>\n<p>16 Se \u00a0refiere \u00a0a \u00a0la \u00a0sentencia \u00a0dictada \u00a0el \u00a021 \u00a0de \u00a0marzo \u00a0de \u00a02007, radicaci\u00f3n N\u00ba \u00a025407. \u00a0\u00a0<\/p>\n<p>17Cfr. \u00a0Auto \u00a0 n\u00fam. \u00a0 28648 \u00a0 del \u00a0 8\/11\/2007, \u00a0 28633 \u00a0 del \u00a014\/11\/2007 \u00a0y \u00a028735 \u00a0del \u00a016\/11\/2007. \u00a0\u00a0<\/p>\n<p>18 \u00a0Cfr. Sentencia de 20 de febrero de 2008, radicaci\u00f3n N\u00ba 28641. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso \u00a0 \u00a0 n.\u00ba \u00a034739 \u00a0\u00a0 CORTE \u00a0 SUPREMA \u00a0 DE \u00a0JUSTICIA \u00a0\u00a0 SALA \u00a0 DE \u00a0 CASACI\u00d3N \u00a0PENAL \u00a0\u00a0 Magistrado Ponente: \u00a0 JULIO ENRIQUE SOCHA SALAMANCA \u00a0 Aprobado Acta N\u00ba 371. \u00a0 Bogot\u00e1 D.C., diecisiete (17) de noviembre de \u00a0dos mil diez (2010). \u00a0\u00a0 VISTOS \u00a0 Decide \u00a0la Sala acerca de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-21362","post","type-post","status-publish","format-standard","hentry","category-18"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/21362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=21362"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/21362\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=21362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=21362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=21362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}