{"id":21245,"date":"2023-09-11T22:55:11","date_gmt":"2023-09-11T22:55:11","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3439815-09-10\/"},"modified":"2023-09-11T22:55:11","modified_gmt":"2023-09-11T22:55:11","slug":"3439815-09-10","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3439815-09-10\/","title":{"rendered":"34398(15-09-10)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso n.\u00ba 34398 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Magistrado Ponente \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0JULIO ENRIQUE SOCHA SALAMANCA \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0Aprobado Acta No. 293 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D. C., quince (15) de septiembre de \u00a0dos mil diez (2010). \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Decide \u00a0la Sala acerca de la admisibilidad de \u00a0los \u00a0fundamentos \u00a0l\u00f3gicos y de debida argumentaci\u00f3n de la demanda de casaci\u00f3n \u00a0presentada \u00a0por \u00a0la \u00a0parte \u00a0Fiscal \u00a0en \u00a0contra \u00a0del \u00a0fallo \u00a0de segunda instancia \u00a0proferido \u00a0por \u00a0el \u00a0Tribunal \u00a0Superior \u00a0del \u00a0Distrito \u00a0Judicial \u00a0de Bogot\u00e1, que \u00a0revoc\u00f3 \u00a0 la \u00a0sentencia \u00a0condenatoria \u00a0emitida \u00a0por \u00a0el \u00a0Juzgado \u00a0D\u00e9cimo \u00a0Penal \u00a0Municipal \u00a0con \u00a0Funciones \u00a0de \u00a0Conocimiento \u00a0de \u00a0esta \u00a0ciudad \u00a0y, \u00a0en \u00a0su lugar, \u00a0absolvi\u00f3 \u00a0a \u00a0los \u00a0procesados YEISON GONZALO MART\u00cdNEZ CAMACHO y DORIS ELIZABETH \u00a0CAMACHO \u00a0DUARTE \u00a0del \u00a0delito de abuso de condiciones de \u00a0inferioridad. \u00a0\u00a0<\/p>\n<p>HECHOS Y ANTECEDENTES PROCESALES \u00a0<\/p>\n<p>1. \u00a0La situaci\u00f3n \u00a0f\u00e1ctica \u00a0que \u00a0suscit\u00f3 \u00a0esta \u00a0actuaci\u00f3n \u00a0fue \u00a0descrita en forma extensa por la \u00a0segunda instancia de la siguiente manera: \u00a0\u00a0<\/p>\n<p>\u201cEst\u00e1 probado en \u00a0el \u00a0proceso \u00a0que Eduardo Garz\u00f3n era hijo de Mar\u00eda, hermano de Jaime, \u00c1lvaro y \u00a0V\u00edctor, \u00a0docente y rector a lo largo de su vida en varios colegios de provincia \u00a0de \u00a0Cundinamarca, v\u00edctima de violaci\u00f3n sexual por un superior en un seminario, \u00a0homosexual, \u00a0intent\u00f3 \u00a0tener \u00a0relaci\u00f3n \u00a0sexual \u00a0con \u00a0alguno de sus hermanos, su \u00a0condici\u00f3n \u00a0sexual \u00a0fue \u00a0conocida \u00a0y \u00a0respetada \u00a0por \u00a0toda su familia, tuvo como \u00a0parejo \u00a0 sexual \u00a0a \u00a0Gabriel \u00a0Navarro, \u00a0fue \u00a0una \u00a0persona \u00a0inteligente, \u00a0educada, \u00a0responsable \u00a0y \u00a0solidario \u00a0con \u00a0su \u00a0mam\u00e1 y hermanos quienes nunca le conocieron \u00a0novia \u00a0o \u00a0mujer, \u00a0normalmente \u00a0vivi\u00f3 \u00a0con \u00a0\u00e9stos \u00a0hasta \u00a0el \u00a015 \u00a0de \u00a0abril \u00a0de \u00a02006. \u00a0\u00a0<\/p>\n<p>\u201dConoci\u00f3 a DORIS \u00a0ELIZABETH \u00a0CAMACHO \u00a0DUARTE \u00a0y \u00a0su \u00a0hijo YEISON GONZALO \u00a0MART\u00cdNEZ \u00a0 \u00a0CAMACHO \u00a0 \u00a0hacia \u00a0 1990 \u00a0 en \u00a0 Vergara, \u00a0 Cundinamarca, \u00a0cuando fue rector de colegio en ese municipio, se reencontr\u00f3 con \u00a0YEISON \u00a0en \u00a0Bogot\u00e1 \u00a0hacia \u00a01991, \u00a0mantuvo con \u00e9ste y su mam\u00e1 una relaci\u00f3n de \u00a0afecto \u00a0a \u00a0partir \u00a0de entonces, tambi\u00e9n con la posterior compa\u00f1era sentimental \u00a0de \u00a0YEISON, \u00a0Rosmira, \u00a0pareja que ha tenido dos hijos a los que tambi\u00e9n Eduardo \u00a0am\u00f3 \u00a0y \u00a0protegi\u00f3 \u00a0entra\u00f1ablemente. \u00a0Seg\u00fan \u00a0el \u00a0\u00e1mbito donde se encontraran, \u00a0Eduardo \u00a0presentaba \u00a0a \u00a0YEISON \u00a0como hijo, sobrino o vecino. Hacia 1995, Eduardo \u00a0compr\u00f3 \u00a0un \u00a0apartamento \u00a0y \u00a0en \u00a0\u00e9l \u00a0han \u00a0vivido \u00a0desde entonces DORIS, YEISON, \u00a0Rosmira \u00a0y \u00a0sus hijos. All\u00ed fue conocido Eduardo como due\u00f1o, o como habitante, \u00a0o \u00a0como \u00a0parejo \u00a0de \u00a0DORIS \u00a0por \u00a0algunos \u00a0de \u00a0sus \u00a0amigos \u00a0y \u00a0testigos \u00a0en \u00a0este \u00a0juicio \u00a0\u00a0<\/p>\n<p>\u201dEduardo cre\u00f3 \u00a0voluntariamente \u00a0un \u00a0fuerte \u00a0nivel \u00a0de \u00a0dependencia \u00a0suya \u00a0frente \u00a0a YEISON y su \u00a0familia, \u00a0 \u00a0al \u00a0 \u00a0punto \u00a0 de \u00a0 que \u00a0 \u2013dicho \u00a0 y \u00a0 reconocido \u00a0 por \u00a0 su \u00a0 parejo \u00a0 Gabriel \u00a0 y \u00a0 por \u00a0sus \u00a0hermanos\u2013 a veces ten\u00eda \u00a0que \u00a0pedirles \u00a0pr\u00e9stamos \u00a0mientras \u00a0se \u00a0encontraba con YEISON para que le diera \u00a0dinero, \u00a0ya \u00a0que \u00e9ste era quien manejaba su tarjeta, hac\u00eda el mercado, etc. Le \u00a0interes\u00f3 \u00a0proteger \u00a0a \u00a0YEISON y familia hasta el punto de adquirir dos p\u00f3lizas \u00a0de \u00a0seguro \u00a0de \u00a0vida \u00a0en \u00a0su \u00a0favor, \u00a0aunque una no termin\u00f3 de pagarla al darse \u00a0cuenta de que una cl\u00e1usula negaba el pago si mor\u00eda por sida. \u00a0\u00a0<\/p>\n<p>\u201dLa familia de \u00a0Eduardo \u00a0conoc\u00eda \u00a0a \u00a0Gabriel Navarro, a YEISON, Rosmira e hijos; eventualmente, \u00a0los recib\u00edan en casa, en fiestas y celebraciones especiales. \u00a0\u00a0<\/p>\n<p>\u201dEduardo \u00a0contrajo \u00a0el \u00a0VIH, \u00a0el \u00a0que se manifest\u00f3 hacia el 2005. A comienzos de 2006, no \u00a0pudo \u00a0seguir \u00a0trabajando \u00a0por \u00a0variados \u00a0s\u00edntomas \u00a0como \u00a0p\u00e9rdida \u00a0de fuerzas y \u00a0diarrea \u00a0cr\u00f3nica. \u00a0Se recluy\u00f3 en casa de su mam\u00e1, quien lo atend\u00eda dentro de \u00a0sus \u00a0posibilidades, \u00a0ya \u00a0que \u00a0muchos \u00a0a\u00f1os \u00a0atr\u00e1s sufri\u00f3 una trombosis que la \u00a0limit\u00f3 \u00a0parcialmente, especialmente de la mano derecha. Tambi\u00e9n lo atend\u00eda su \u00a0hermano \u00a0\u00c1lvaro, pero \u2013al \u00a0decir \u00a0de \u00a0la mam\u00e1\u2013 a los \u00a0hermanos les daba asco esta situaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u201dEl 15 de abril \u00a0de \u00a02006, \u00a0YEISON \u00a0visit\u00f3 \u00a0a \u00a0Eduardo y lo encontr\u00f3 en mal estado, pidi\u00f3 a la \u00a0mam\u00e1 \u00a0que \u00a0se \u00a0lo \u00a0dejara \u00a0llevar a una cl\u00ednica para que lo viera un m\u00e9dico y \u00a0regresarlo \u00a0despu\u00e9s, \u00a0no se encontraban los hermanos y ella accedi\u00f3; estuvo en \u00a0cl\u00ednica \u00a0tres \u00a0d\u00edas \u00a0y \u00a0YEISON lo llev\u00f3 a su apartamento, all\u00ed fue visto por \u00a0algunos \u00a0amigos \u00a0bien atendido, aseado, visitado por un m\u00e9dico bioenerg\u00e9tico y \u00a0una \u00a0enfermera; \u00a0otra \u00a0enfermera amiga y vecina lo visitaba espor\u00e1dicamente. La \u00a0familia \u00a0de \u00a0Eduardo, \u00a0su \u00a0parejo Gabriel y su amigo Antonio Clavijo afirman que \u00a0YEISON \u00a0y \u00a0familia \u00a0no \u00a0dejaron \u00a0visitarlo \u00a0o lo negaban con varias excusas como \u00a0estar \u00a0dormido, \u00a0estarlo \u00a0ba\u00f1ando, estar con el m\u00e9dico, etc. Mar\u00eda, la mam\u00e1, \u00a0dice \u00a0que trat\u00f3 de visitar en una ocasi\u00f3n a Eduardo en el apartamento. Maribel \u00a0Charris \u00a0dice que Eduardo se qued\u00f3 llorando un d\u00eda porque la mam\u00e1 lo visit\u00f3, \u00a0\u00e9l le pidi\u00f3 que se quedara, pero ella no quiso hacerlo. \u00a0\u00a0<\/p>\n<p>\u201dEl \u00a0 cura \u00a0p\u00e1rroco \u00a0del \u00a0sector, Julio C\u00e9sar Montilla, relata que a comienzos de julio de \u00a02006 \u00a0YEISON se present\u00f3 a su despacho para pedirle que casara a Eduardo, quien \u00a0en \u00a0peligro de muerte quer\u00eda hacerlo con DORIS; que estos matrimonios se pueden \u00a0celebrar \u00a0inmediatamente pero \u00e9l prefiri\u00f3 seguir un procedimiento completo, le \u00a0pidi\u00f3 \u00a0allegar \u00a0los \u00a0documentos \u00a0necesarios, \u00a0las \u00a0partidas \u00a0de bautismo de los \u00a0interesados. \u00a0El \u00a010 \u00a0de \u00a0junio, \u00a0YEISON \u00a0se los llev\u00f3 y por lo tanto qued\u00f3 en \u00a0disposici\u00f3n \u00a0de \u00a0celebrar \u00a0el \u00a0matrimonio, acudi\u00f3 al apartamento que encontr\u00f3 \u00a0limpio \u00a0y \u00a0dispuesto, estuvieron presentes los contrayentes, los padrinos YEISON \u00a0y \u00a0Consuelo \u00a0Ni\u00f1o, Rosmira y sus hijos; elabor\u00f3 el expediente matrimonial como \u00a0est\u00e1 \u00a0previsto \u00a0en \u00a0las \u00a0normas \u00a0can\u00f3nicas, encontr\u00f3 a EDUARDO acostado en su \u00a0cama, \u00a0pero \u00a0l\u00facido y consciente de ante qui\u00e9n se encontraba, qui\u00e9nes estaban \u00a0presentes, \u00a0qu\u00e9 acto se realizaba. Dijo Eduardo que estaba en peligro de muerte \u00a0por \u00a0un c\u00e1ncer intestinal. Procedi\u00f3 el sacerdote a registrar los datos de cada \u00a0uno \u00a0 de \u00a0 los \u00a0contrayentes, \u00a0luego \u00a0a \u00a0la \u00a0verificaci\u00f3n \u00a0del \u00a0conocimiento \u00a0y \u00a0consentimiento \u00a0de \u00a0cada \u00a0uno \u00a0en \u00a0el matrimonio, continu\u00f3 con el requisito del \u00a0sacramento de confesi\u00f3n y finalmente celebr\u00f3 el matrimonio. \u00a0\u00a0<\/p>\n<p>\u201dEl \u00a013 \u00a0de \u00a0septiembre \u00a0de \u00a02006, \u00a0Eduardo \u00a0falleci\u00f3. Informada su familia, acudieron a las \u00a0Capillas \u00a0de la Fe, donde su hermano Jaime observ\u00f3 que los carteles dec\u00edan que \u00a0Eduardo \u00a0era \u00a0casado \u00a0con DORIS, le indag\u00f3 a YEISON y \u00e9ste le dijo que ten\u00edan \u00a0que \u00a0hablar, \u00a0hacer \u00a0una \u00a0reuni\u00f3n para ese fin. Tiempo despu\u00e9s, Jaime intent\u00f3 \u00a0tramitar \u00a0la \u00a0pensi\u00f3n \u00a0de \u00a0Eduardo para su mam\u00e1 Mar\u00eda ante la Gobernaci\u00f3n de \u00a0Cundinamarca, \u00a0y all\u00ed le informaron que no era posible, pues le correspond\u00eda a \u00a0la \u00a0 esposa, \u00a0 DORIS, \u00a0 a \u00a0 quien \u00a0 en \u00a0efecto \u00a0despu\u00e9s \u00a0le \u00a0fue \u00a0reconocida \u00a0y \u00a0pagada. \u00a0\u00a0<\/p>\n<p>\u201dJaime Garz\u00f3n \u00a0present\u00f3 \u00a0denuncia \u00a0en \u00a0la \u00a0Fiscal\u00eda \u00a0para \u00a0que \u00a0se investigara la conducta de \u00a0YEISON \u00a0y \u00a0DORIS por cuanto habr\u00edan perjudicado a la mam\u00e1 y familia de Eduardo \u00a0al \u00a0inducirlo \u00a0a \u00a0contraer \u00a0matrimonio \u00a0en \u00a0condiciones \u00a0que no pod\u00eda tomar esa \u00a0decisi\u00f3n\u201d. \u00a0\u00a0<\/p>\n<p>2. \u00a0Debido \u00a0a \u00a0lo \u00a0anterior, \u00a0la \u00a0Fiscal\u00eda \u00a0General de la Naci\u00f3n formul\u00f3 acusaci\u00f3n en contra de \u00a0YEISON \u00a0GONZALO \u00a0MART\u00cdNEZ \u00a0CAMACHO y DORIS ELIZABETH CAMACHO DUARTE, el primero \u00a0en \u00a0calidad \u00a0de \u00a0c\u00f3mplice \u00a0y \u00a0la \u00a0segunda \u00a0a t\u00edtulo de autora, por la conducta \u00a0punible \u00a0 \u00a0 de \u00a0 \u00a0 abuso \u00a0 \u00a0de \u00a0 \u00a0condiciones \u00a0 \u00a0de \u00a0inferioridad, \u00a0de \u00a0conformidad \u00a0con lo previsto en el \u00a0art\u00edculo \u00a0251 \u00a0incisos \u00a01\u00ba \u00a0y 2\u00ba de la Ley 599 de 2000, actual C\u00f3digo Penal, \u00a0con \u00a0la \u00a0modificaci\u00f3n \u00a0introducida \u00a0por \u00a0el \u00a0art\u00edculo \u00a014 \u00a0de \u00a0la \u00a0Ley \u00a0890 de \u00a02004. \u00a0\u00a0<\/p>\n<p>3. \u00a0El juicio oral \u00a0lo \u00a0adelant\u00f3 \u00a0el \u00a0Juzgado D\u00e9cimo Penal Municipal con Funciones de Conocimiento \u00a0de \u00a0Bogot\u00e1, \u00a0despacho \u00a0que \u00a0por \u00a0el delito en comento declar\u00f3 al primero autor \u00a0[sic], \u00a0conden\u00e1ndolo a la pena principal de treinta y cinco meses de prisi\u00f3n y \u00a0siete \u00a0salarios \u00a0m\u00ednimos \u00a0legales \u00a0mensuales vigentes de multa; y a la segunda, \u00a0como \u00a0c\u00f3mplice \u00a0[sic], \u00a0a \u00a0la \u00a0de diecinueve meses de prisi\u00f3n y siete salarios \u00a0m\u00ednimos \u00a0de \u00a0multa. As\u00ed mismo, los sentenci\u00f3 a las accesorias de inhabilitaci\u00f3n \u00a0 para \u00a0 el \u00a0 ejercicio \u00a0de \u00a0derechos \u00a0y \u00a0funciones \u00a0p\u00fablicas \u00a0por \u00a0un tiempo igual al de las respectivas \u00a0sanciones \u00a0privativas \u00a0de la libertad y les concedi\u00f3 la suspensi\u00f3n condicional \u00a0por un periodo de prueba de dos a\u00f1os. \u00a0\u00a0<\/p>\n<p>4. \u00a0Apelada \u00a0la \u00a0providencia \u00a0 por \u00a0 el \u00a0defensor \u00a0del \u00a0procesado, \u00a0el \u00a0Tribunal \u00a0Superior \u00a0del \u00a0Distrito \u00a0Judicial \u00a0de \u00a0Bogot\u00e1 \u00a0la \u00a0revoc\u00f3 \u00a0de manera \u00a0integral \u00a0y, \u00a0en \u00a0su \u00a0lugar, \u00a0absolvi\u00f3 \u00a0a los procesados de los hechos y cargos \u00a0materia de acusaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Seg\u00fan el ad quem, el comportamiento juzgado \u00a0era \u00a0at\u00edpico, \u00a0por cuanto el sujeto pasivo contrajo l\u00edcitamente el matrimonio, \u00a0es \u00a0decir, \u00a0de forma voluntaria, informada, aquiescente y l\u00facida, raz\u00f3n por la \u00a0cual \u00a0no \u00a0era posible condenar a un tercero por haber incidido en tal decisi\u00f3n, \u00a0ni mucho menos a la contrayente como c\u00f3mplice de tal influencia. \u00a0\u00a0<\/p>\n<p>Igualmente, destac\u00f3 entre otras razones que \u00a0es \u00a0 indiferente \u00a0 tanto \u00a0la \u00a0determinaci\u00f3n \u00a0de \u00a0la \u00a0orientaci\u00f3n \u00a0sexual \u00a0de \u00a0los \u00a0esponsales \u00a0como la necesidad de establecer si la \u00a0uni\u00f3n \u00a0se \u00a0consum\u00f3 \u00a0o \u00a0no, aspectos que fueron tenidos en cuenta por el a quo, \u00a0m\u00e1xime \u00a0cuando \u00a0el \u00a0acto \u00a0capaz \u00a0de \u00a0producir \u00a0efectos jur\u00eddicos no perjudic\u00f3 \u00a0econ\u00f3micamente \u00a0al \u00a0titular \u00a0del \u00a0bien jur\u00eddico (es decir, a Eduardo Garz\u00f3n), \u00a0sino a otras personas. \u00a0\u00a0<\/p>\n<p>5. Contra el fallo \u00a0de \u00a0segundo \u00a0grado, \u00a0el \u00a0representante de la Fiscal\u00eda \u00a0interpuso el recurso extraordinario de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>Al amparo del numeral 1 del art\u00edculo 181 de \u00a0la \u00a0Ley \u00a0906 de 2004, el recurrente plante\u00f3 la violaci\u00f3n directa del art\u00edculo \u00a0251 \u00a0de \u00a0la \u00a0Ley \u00a0599 \u00a0de \u00a02000 \u00a0por interpretaci\u00f3n err\u00f3nea del precepto all\u00ed \u00a0contenido. \u00a0\u00a0<\/p>\n<p>Al \u00a0respecto, \u00a0adujo \u00a0que \u00a0lo \u00a0dicho \u00a0por el \u00a0Tribunal \u00a0es contrario a derecho, pues la norma contempla al tercero perjudicado \u00a0como \u00a0elemento \u00a0t\u00edpico, en la medida en que de acuerdo con la jurisprudencia de \u00a0la \u00a0Corte Interamericana del Derechos Humanos y la de la Corte Constitucional no \u00a0s\u00f3lo \u00a0son \u00a0v\u00edctimas \u00a0los \u00a0afectados \u00a0directos \u00a0con \u00a0la \u00a0conducta punible, sino \u00a0adem\u00e1s sus familiares. \u00a0\u00a0<\/p>\n<p>Agreg\u00f3 \u00a0que el ad quem confundi\u00f3 la figura \u00a0de \u00a0la \u00a0inferioridad con el estado de plena lucidez, porque no es necesario para \u00a0considerar \u00a0configurada \u00a0la primera que la persona est\u00e9 inconsciente o presente \u00a0trastorno \u00a0mental \u00a0y, \u00a0por \u00a0el contrario, basta una interferencia en las esferas \u00a0volitiva \u00a0e \u00a0intelectiva de la v\u00edctima para conducirla a un acto perjudicial al \u00a0patrimonio econ\u00f3mico. \u00a0\u00a0<\/p>\n<p>En \u00a0consecuencia, solicit\u00f3 a la Corte casar \u00a0la \u00a0sentencia \u00a0impugnada \u00a0para \u00a0en \u00a0su lugar condenar a YEISON GONZALO MART\u00cdNEZ \u00a0CAMACHO \u00a0y \u00a0a \u00a0DORIS \u00a0ELIZABETH \u00a0CAMACHO \u00a0DUARTE \u00a0por \u00a0el delito de abuso \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0condiciones \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 inferioridad. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0<\/p>\n<p>1. \u00a0De conformidad \u00a0con \u00a0lo \u00a0establecido \u00a0en \u00a0el \u00a0art\u00edculo \u00a0181 \u00a0de \u00a0la Ley 906 de 2004, C\u00f3digo de \u00a0Procedimiento \u00a0Penal \u00a0vigente \u00a0para \u00a0este \u00a0asunto, el recurso de casaci\u00f3n es un \u00a0mecanismo \u00a0de \u00a0control \u00a0tanto \u00a0constitucional \u00a0como legal que procede contra los \u00a0fallos \u00a0proferidos en segunda instancia y que, de acuerdo con lo se\u00f1alado en el \u00a0art\u00edculo \u00a0180 ib\u00eddem, tiene como prop\u00f3sitos lograr la efectividad del derecho \u00a0material, \u00a0el \u00a0respeto \u00a0de \u00a0las \u00a0garant\u00edas fundamentales, la reparaci\u00f3n de los \u00a0agravios inferidos y la unificaci\u00f3n de la jurisprudencia. \u00a0\u00a0<\/p>\n<p>Dada \u00a0la \u00a0naturaleza \u00a0extraordinaria de este \u00a0recurso, \u00a0 quien \u00a0acude \u00a0a \u00a0la \u00a0casaci\u00f3n \u00a0tiene \u00a0que \u00a0ce\u00f1irse \u00a0a \u00a0determinados requerimientos sistem\u00e1ticos \u00a0basados \u00a0en \u00a0la \u00a0raz\u00f3n \u00a0y \u00a0en \u00a0la \u00a0l\u00f3gica \u00a0argumentativa, \u00a0as\u00ed \u00a0como \u00a0guardar \u00a0coherencia, \u00a0precisi\u00f3n \u00a0y \u00a0claridad \u00a0en el sustento de cada uno de los reparos, \u00a0que \u00a0debe \u00a0desarrollar conforme a las causales previstas en el art\u00edculo 181 del \u00a0ordenamiento procesal. \u00a0\u00a0<\/p>\n<p>A su vez, el inciso 2\u00ba del art\u00edculo 184 del \u00a0referido \u00a0estatuto \u00a0se\u00f1ala \u00a0que \u00a0no \u00a0ser\u00e1 \u00a0admitida \u00a0la \u00a0demanda \u00a0de casaci\u00f3n \u00a0\u201ccuando de su contexto se advierta fundadamente que \u00a0no \u00a0 se \u00a0 precisa \u00a0 del \u00a0fallo \u00a0para \u00a0cumplir \u00a0alguna \u00a0de \u00a0las \u00a0finalidades \u00a0del \u00a0recurso\u201d, \u00a0lo \u00a0que \u00a0puede \u00a0darse \u00a0cuando \u00a0la \u00a0Corte \u00a0encuentre \u00a0 que \u00a0la \u00a0controversia \u00a0planteada \u00a0carece \u00a0de \u00a0incidencia \u00a0alguna \u00a0en \u00a0relaci\u00f3n \u00a0con \u00a0lo \u00a0decidido \u00a0en \u00a0el caso concreto, o que podr\u00e1 responder a los \u00a0planteamientos \u00a0del \u00a0recurrente \u00a0sin \u00a0tener \u00a0que \u00a0efectuar valoraciones de fondo \u00a0acerca de lo que ocurri\u00f3 en la actuaci\u00f3n. \u00a0\u00a0<\/p>\n<p>2. \u00a0En el asunto \u00a0materia \u00a0de inter\u00e9s, el \u00fanico reproche aducido por la parte Fiscal \u00a0no \u00a0s\u00f3lo \u00a0carece \u00a0de \u00a0sustento \u00a0en \u00a0lo \u00a0relativo \u00a0a \u00a0las cargas \u00a0procesales \u00a0que \u00a0exige \u00a0su invocaci\u00f3n, sino que el problema jur\u00eddico propuesto \u00a0no \u00a0 \u00a0abarca \u00a0 \u00a0todo \u00a0 lo \u00a0 aducido \u00a0 por \u00a0 la \u00a0 segunda \u00a0 instancia. \u00a0\u00a0<\/p>\n<p>En efecto, cuando \u00a0en \u00a0sede de casaci\u00f3n se formula la violaci\u00f3n directa de la ley sustancial, tal \u00a0como \u00a0lo \u00a0hizo \u00a0el \u00a0demandante, \u00a0la \u00a0Corte \u00a0ha \u00a0sido \u00a0enf\u00e1tica y reiterativa al \u00a0se\u00f1alar \u00a0que \u00a0a \u00a0\u00e9ste \u00a0le \u00a0asiste \u00a0la obligaci\u00f3n de demostrar que el Tribunal \u00a0incurri\u00f3 \u00a0en \u00a0un \u00a0yerro en la selecci\u00f3n o en la comprensi\u00f3n de la norma, bien \u00a0sea \u00a0 porque \u00a0no \u00a0reconoci\u00f3 \u00a0la \u00a0ley \u00a0llamada \u00a0a \u00a0regular \u00a0el \u00a0caso \u00a0(falta \u00a0de \u00a0aplicaci\u00f3n), \u00a0o \u00a0ajust\u00f3 \u00a0de \u00a0manera \u00a0incorrecta \u00a0el supuesto f\u00e1ctico a lo que \u00a0contempla \u00a0otra \u00a0disposici\u00f3n \u00a0(aplicaci\u00f3n \u00a0indebida), \u00a0o \u00a0asign\u00f3 \u00a0al precepto \u00a0elegido \u00a0de \u00a0manera \u00a0adecuada \u00a0un \u00a0sentido \u00a0o \u00a0efecto \u00a0contrario \u00a0a su contenido \u00a0(interpretaci\u00f3n err\u00f3nea). \u00a0\u00a0<\/p>\n<p>Una \u00a0 censura \u00a0 en \u00a0cualquiera \u00a0de \u00a0estas \u00a0modalidades, \u00a0por \u00a0lo \u00a0tanto, \u00a0le \u00a0impone a quien la \u00a0postula \u00a0 la \u00a0 obligaci\u00f3n \u00a0 de \u00a0 aceptar \u00a0 tanto \u00a0 la \u00a0apreciaci\u00f3n \u00a0probatoria \u00a0efectuada \u00a0en \u00a0el fallo impugnado como la situaci\u00f3n \u00a0f\u00e1ctica que se declar\u00f3 demostrada a ra\u00edz de tal valoraci\u00f3n. \u00a0\u00a0<\/p>\n<p>En \u00a0el \u00a0presente \u00a0caso, \u00a0el profesional del \u00a0derecho \u00a0desacert\u00f3 \u00a0al \u00a0plantear \u00a0la \u00a0v\u00eda \u00a0de ataque, pues, por un lado, no es \u00a0posible \u00a0censurarle \u00a0al \u00a0Tribunal \u00a0la interpretaci\u00f3n err\u00f3nea del art\u00edculo 251 \u00a0del \u00a0 C\u00f3digo \u00a0 Penal \u00a0 (que \u00a0 consagra \u00a0la \u00a0conducta \u00a0punible \u00a0de \u00a0abuso \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0condiciones \u00a0 \u00a0 de \u00a0 \u00a0 inferioridad, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u201c[e]l que con el fin de obtener para \u00a0s\u00ed \u00a0o \u00a0para otro un provecho il\u00edcito y abusando de la necesidad, de la pasi\u00f3n \u00a0o \u00a0del \u00a0trastorno \u00a0mental \u00a0de \u00a0una \u00a0persona, o de su inexperiencia, la induzca a \u00a0realizar \u00a0 \u00a0un \u00a0 \u00a0acto \u00a0 capaz \u00a0 de \u00a0 producir \u00a0 efectos \u00a0 jur\u00eddicos \u00a0 que \u00a0 la \u00a0perjudique\u201d), \u00a0pues lo anterior presupone, en sede \u00a0de \u00a0casaci\u00f3n, \u00a0la \u00a0aplicaci\u00f3n \u00a0del \u00a0predicado \u00a0normativo respecto del supuesto \u00a0f\u00e1ctico \u00a0imputado \u00a0(aunque con un alcance distinto a lo que el primero se\u00f1ala) \u00a0y, \u00a0en \u00a0este \u00a0asunto, salta a la vista que los acusados no fueron condenados por \u00a0ese \u00a0 delito, \u00a0 sino \u00a0 absueltos \u00a0 del \u00a0 mismo, \u00a0 dada \u00a0 la \u00a0atipicidad \u00a0de \u00a0sus \u00a0comportamientos. \u00a0 Es \u00a0 decir, \u00a0 la \u00a0norma \u00a0jur\u00eddica \u00a0jam\u00e1s \u00a0pudo \u00a0haber \u00a0sido \u00a0interpretada \u00a0de \u00a0manera \u00a0err\u00f3nea \u00a0por \u00a0el \u00a0Tribunal, \u00a0porque \u00a0ni \u00a0siquiera \u00a0la \u00a0aplic\u00f3. \u00a0\u00a0<\/p>\n<p>Por otro lado, tampoco mostr\u00f3 el recurrente \u00a0una \u00a0total \u00a0aquiescencia \u00a0respecto \u00a0de \u00a0las \u00a0circunstancias \u00a0f\u00e1cticas que en la \u00a0providencia \u00a0 de \u00a0 segunda \u00a0 instancia \u00a0 se \u00a0estimaron \u00a0demostradas, \u00a0 pues \u00a0 la \u00a0 mayor\u00eda \u00a0de \u00a0los \u00a0criterios \u00a0plasmados \u00a0en \u00a0la \u00a0demanda \u00a0estuvieron \u00a0dirigidos a convencer que a Eduardo \u00a0Garz\u00f3n \u00a0le \u00a0fue \u00a0interferido su normal desempe\u00f1o volitivo cuando se hallaba en \u00a0la \u00a0 fase \u00a0 terminal \u00a0 del \u00a0s\u00edndrome \u00a0de \u00a0inmunodeficiencia \u00a0adquirida, \u00a0estado \u00a0\u201cen \u00a0el cual el paciente se afecta emocionalmente, \u00a0s\u00edquicamente \u00a0 \u00a0 \u00a0 y \u00a0 \u00a0 \u00a0 era \u00a0 \u00a0 \u00a0 f\u00e1cilmente \u00a0 \u00a0 \u00a0influenciable\u201d1. \u00a0\u00a0<\/p>\n<p>Para el cuerpo colegiado, en cambio, el acto \u00a0de \u00a0contraer \u00a0matrimonio que celebr\u00f3 Eduardo Garz\u00f3n fue por completo aut\u00f3nomo \u00a0y deseado: \u00a0\u00a0<\/p>\n<p>\u201cAparece \u00a0informado \u00a0y \u00a0no impugnado que Eduardo expres\u00f3 en algunas ocasiones su deseo de \u00a0no \u00a0dejar \u00a0desamparada \u00a0a \u00a0su \u00a0mam\u00e1, \u00a0como \u00a0que \u00a0siempre hab\u00eda sido su soporte \u00a0econ\u00f3mico. \u00a0Tambi\u00e9n \u00a0aparece que sab\u00eda que su decisi\u00f3n de favorecer a YEISON \u00a0y \u00a0 familia \u00a0 iba \u00a0a \u00a0ser \u00a0causa \u00a0de \u00a0problemas \u00a0con \u00a0sus \u00a0hermanos \u00a0cuando \u00a0\u00e9l \u00a0desapareciera. \u00a0Su voluntad de favorecimiento\u00a0 YEISON y familia, adem\u00e1s de \u00a0haberle \u00a0comprado \u00a0y \u00a0dejado \u00a0disfrutar el apartamento, qued\u00f3 ratificado con el \u00a0hecho \u00a0 de \u00a0 que \u00a0 adquiri\u00f3 \u00a0 dos \u00a0seguros \u00a0de \u00a0vida \u00a0en \u00a0su \u00a0beneficio. \u00a0Estas \u00a0manifestaciones \u00a0del inter\u00e9s de Eduardo se concretan en el acto del matrimonio, \u00a0con \u00a0lo \u00a0cual \u00a0no \u00a0se \u00a0puede sino afirmar que hizo una opci\u00f3n personal, libre y \u00a0voluntaria \u00a0de hacer prevalecer la protecci\u00f3n de YEISON y familia, posiblemente \u00a0considerando \u00a0que \u00a0la \u00a0mam\u00e1 \u00a0ten\u00eda \u00a0otros \u00a0tres \u00a0hijos \u00a0sup\u00e9rstites que no la \u00a0abandonar\u00edan \u00a0\u2013aunque \u00a0esta \u00a0es \u00a0una \u00a0deducci\u00f3n \u00a0de \u00a0los \u00a0hechos \u00a0del \u00a0entorno y no una afirmaci\u00f3n de \u00a0parte\u201d2. \u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0mismo, \u00a0cuestion\u00f3 \u00a0el \u00a0recurrente el \u00a0alcance \u00a0 \u00a0del \u00a0 \u00a0elemento \u00a0 \u00a0t\u00edpico \u00a0 \u201cque \u00a0 la \u00a0perjudique\u201d, en el sentido de que el sujeto pasivo \u00a0o \u00a0el \u00a0titular del bien jur\u00eddico no es tan s\u00f3lo la persona que realiza el acto \u00a0capaz \u00a0de \u00a0producir efectos jur\u00eddicos bajo circunstancias de necesidad, pasi\u00f3n \u00a0o \u00a0trastorno \u00a0mental, \u00a0sino \u00a0tambi\u00e9n los allegados que a la vez terminen siendo \u00a0perjudicados en sus intereses econ\u00f3micos. \u00a0\u00a0<\/p>\n<p>Resulta \u00a0inocuo \u00a0entrar \u00a0a \u00a0analizar si tal \u00a0postura \u00a0es \u00a0ajustada \u00a0a \u00a0derecho, \u00a0debido \u00a0a \u00a0que el fallo de segunda instancia \u00a0respalda \u00a0 la \u00a0atipicidad \u00a0de \u00a0los \u00a0hechos \u00a0materia \u00a0de \u00a0juicio \u00a0con \u00a0argumentos \u00a0diferentes \u00a0a \u00a0los cuestionados en la demanda, entre ellos el de que lo sucedido \u00a0no \u00a0escap\u00f3 \u00a0de \u00a0la \u00a0\u00f3rbita \u00a0de \u00a0lo \u00a0privado \u00a0y, \u00a0por consiguiente, careci\u00f3 de \u00a0trascendencia \u00a0jur\u00eddico \u00a0penal. \u00a0Ello \u00a0se advierte en el largo relato que de la \u00a0situaci\u00f3n \u00a0f\u00e1ctica \u00a0hizo \u00a0el Tribunal, as\u00ed como en las cr\u00edticas realizadas a \u00a0la decisi\u00f3n adoptada por el a quo, que son del siguiente tenor: \u00a0\u00a0<\/p>\n<p>\u201c[\u2026] \u00a0se \u00a0enfrasca \u00a0la \u00a0sentencia \u00a0apelada \u00a0en considerar los testimonios de los amigos de \u00a0Eduardo \u00a0que \u00a0al parecer no sab\u00edan de su condici\u00f3n homosexual, nunca lo vieron \u00a0darse \u00a0besos \u00a0o abrazos con DORIS, o s\u00f3lo ve\u00edan que hab\u00eda alguna relaci\u00f3n de \u00a0cari\u00f1o \u00a0pero \u00a0no \u00a0como \u00a0de \u00a0pareja; \u00a0en \u00a0que la mam\u00e1, Jaime, Antonio Clavijo y \u00a0Gabriel \u00a0Navarro \u00a0sab\u00edan \u00a0de \u00a0su condici\u00f3n de homosexual y por lo tanto que no \u00a0tendr\u00eda \u00a0relaci\u00f3n \u00a0de pareja con DORIS; la siquiatra de Medicina Legal adem\u00e1s \u00a0afirma \u00a0que \u00a0no \u00a0es \u00a0posible que una persona que ha sido homosexual toda la vida \u00a0haya \u00a0cambiado \u00a0a \u00a0\u00faltima hora su preferencia sexual. No acierta la providencia \u00a0en \u00a0esas elucubraciones, ya que no es un requisito de validez para el matrimonio \u00a0que \u00a0se \u00a0tenga \u00a0capacidad \u00a0para la relaci\u00f3n sexual entre los contrayentes o que \u00a0\u00e9sta \u00a0se \u00a0perfeccione; \u00a0aunque \u00a0uno \u00a0de \u00a0sus \u00a0fines sea el de procrear, es solo \u00a0causal \u00a0 de \u00a0 anulaci\u00f3n \u00a0 que \u00a0 puede \u00a0 alegar \u00a0 el \u00a0 impedimento \u00a0in \u00a0 \u00a0 coeundi \u00a0 \u00a0 o \u00a0 \u00a0in \u00a0 \u00a0generandi, \u00a0 \u00a0esto \u00a0 \u00a0es, \u00a0 la \u00a0imposibilidad \u00a0de \u00a0erecci\u00f3n \u00a0viril o la de fecundar. No le est\u00e1 dado a ning\u00fan \u00a0tercero alegarlo, ni inmiscuirse en ello. \u00a0\u00a0<\/p>\n<p>\u201d[\u2026] \u00a0La \u00a0decisi\u00f3n \u00a0 que \u00a0se \u00a0revoca \u00a0parece \u00a0querer \u00a0cumplir \u00a0con \u00a0el \u00a0imperativo \u00a0moral \u00a0\u2013aceptable \u00a0 \u00a0 y \u00a0plausible\u2013 \u00a0 \u00a0del \u00a0cumplimiento \u00a0del \u00a0deber \u00a0de \u00a0asistencia \u00a0a \u00a0los \u00a0ascendientes \u00a0y con la cultura \u00a0religiosa \u00a0 \u00a0 \u00a0 dominante \u00a0 \u00a0 \u00a0 \u2013incluye \u00a0 \u00a0 \u00a0 \u00a0 \u2018los \u00a0 fines \u00a0 del \u00a0 matrimonio \u00a0 de \u00a0 acuerdo \u00a0 con \u00a0 la \u00a0doctrina \u00a0cat\u00f3lica\u2019 \u00a0 en \u00a0 la \u00a0p\u00e1gina \u00a018\u2013, y por eso \u00a0no \u00a0deriva \u00a0las \u00a0consecuencias propias de los hallazgos probados y de las normas \u00a0que \u00a0invoca. \u00a0Sin embargo, debe recordarse que el orden jur\u00eddico es laico en un \u00a0Estado \u00a0de \u00a0Derecho \u00a0con \u00a0libertad de cultos, donde lo que prevalece es la norma \u00a0positiva \u00a0legalmente \u00a0establecida y sus interpretaciones autorizadas\u201d3. \u00a0\u00a0<\/p>\n<p>En \u00a0consecuencia, como la Sala concluye que \u00a0el \u00a0reproche \u00a0carece \u00a0de \u00a0fundamentos, \u00a0y \u00a0como tampoco observa con ocasi\u00f3n del \u00a0tr\u00e1mite \u00a0procesal \u00a0o \u00a0de \u00a0la \u00a0sentencia \u00a0impugnada \u00a0violaci\u00f3n \u00a0del \u00a0debido \u00a0proceso \u00a0ni \u00a0de los derechos \u00a0fundamentales \u00a0de \u00a0las \u00a0v\u00edctimas, \u00a0ni \u00a0mucho \u00a0menos \u00a0la necesidad de garantizar \u00a0cualquiera \u00a0de \u00a0los \u00a0fines de la casaci\u00f3n mediante un pronunciamiento de fondo, \u00a0no \u00a0hay \u00a0raz\u00f3n \u00a0alguna para superar las falencias que ostenta la demanda y, por \u00a0lo \u00a0tanto, \u00a0\u00e9sta no ser\u00e1 admitida, tal como est\u00e1 previsto en el art\u00edculo 184 \u00a0de la ley 906 de 2004. \u00a0\u00a0<\/p>\n<p>3. \u00a0Teniendo en \u00a0cuenta \u00a0 que \u00a0 contra \u00a0 la \u00a0 decisi\u00f3n \u00a0de \u00a0no \u00a0admitir \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0procede \u00a0el \u00a0mecanismo \u00a0de insistencia, seg\u00fan lo \u00a0establece \u00a0el inciso 2\u00ba de la norma en comento, es menester aclarar que la Sala \u00a0ha \u00a0precisado \u00a0la \u00a0naturaleza \u00a0y \u00a0reglas \u00a0que \u00a0habr\u00e1n \u00a0de \u00a0observarse \u00a0para \u00a0su \u00a0aplicaci\u00f3n \u00a0 \u00a0 de \u00a0 \u00a0 la \u00a0 \u00a0siguiente \u00a0 \u00a0manera4: \u00a0\u00a0<\/p>\n<p>3.1. \u00a0 \u00a0La \u00a0insistencia \u00a0es un mecanismo especial, de naturaleza \u00a0distinta \u00a0a \u00a0los \u00a0actos \u00a0de impugnaci\u00f3n propiamente dichos, que s\u00f3lo puede ser \u00a0promovido \u00a0por \u00a0el \u00a0demandante \u00a0dentro \u00a0de \u00a0los \u00a0cinco \u00a0d\u00edas \u00a0siguientes \u00a0a \u00a0la \u00a0notificaci\u00f3n \u00a0de \u00a0la \u00a0providencia mediante la cual decide no admitir la demanda \u00a0de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>3.2. La solicitud \u00a0de \u00a0insistencia \u00a0puede ser elevada ante el Ministerio P\u00fablico por intermedio de \u00a0cualquiera \u00a0de \u00a0sus \u00a0Delegados \u00a0para \u00a0la \u00a0casaci\u00f3n \u00a0penal, \u00a0o \u00a0ante \u00a0uno de los \u00a0Magistrados \u00a0que \u00a0hayan \u00a0salvado el voto en cuanto a la decisi\u00f3n mayoritaria de \u00a0no \u00a0admisi\u00f3n, \u00a0o \u00a0ante \u00a0uno \u00a0de \u00a0los \u00a0Magistrados que no haya intervenido en la \u00a0discusi\u00f3n \u00a0 \u00a0 y \u00a0 \u00a0no \u00a0 \u00a0haya \u00a0 \u00a0suscrito \u00a0 \u00a0el \u00a0 \u00a0referido \u00a0 \u00a0auto. \u00a0\u00a0<\/p>\n<p>3.3. \u00a0 Es \u00a0facultativo \u00a0del Magistrado disidente, del que no intervino en los debates o del \u00a0Delegado \u00a0del \u00a0Ministerio \u00a0P\u00fablico \u00a0ante quien se formula la insistencia, optar \u00a0por \u00a0someter \u00a0el \u00a0asunto \u00a0a \u00a0consideraci\u00f3n \u00a0de la Sala o no presentarlo para su \u00a0revisi\u00f3n, \u00a0evento \u00faltimo en el que informar\u00e1 de ello al solicitante dentro de \u00a0un plazo de quince d\u00edas. \u00a0\u00a0<\/p>\n<p>3.4. \u00a0El \u00a0auto \u00a0mediante \u00a0el \u00a0cual \u00a0no se admite la demanda trae como consecuencia la firmeza de \u00a0la \u00a0sentencia \u00a0contra \u00a0la \u00a0que se formul\u00f3 el recurso de casaci\u00f3n, salvo que la \u00a0insistencia prospere y conduzca a la admisi\u00f3n del escrito. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito de lo expuesto, la CORTE \u00a0 \u00a0 SUPREMA \u00a0 \u00a0DE \u00a0 \u00a0JUSTICIA, \u00a0SALA \u00a0 \u00a0 \u00a0DE \u00a0 \u00a0 CASACI\u00d3N \u00a0 \u00a0 PENAL, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>NO \u00a0ADMITIR \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0allegada por el representante de la Fiscal\u00eda General de \u00a0la \u00a0Naci\u00f3n \u00a0en \u00a0contra \u00a0del \u00a0fallo \u00a0de segundo grado \u00a0proferido \u00a0 \u00a0por \u00a0 \u00a0el \u00a0 \u00a0Tribunal \u00a0 \u00a0Superior \u00a0 \u00a0del \u00a0 Distrito \u00a0 Judicial \u00a0 de \u00a0Bogot\u00e1. \u00a0\u00a0<\/p>\n<p>De \u00a0conformidad \u00a0con \u00a0lo \u00a0dispuesto \u00a0en \u00a0el \u00a0art\u00edculo \u00a0184 \u00a0de \u00a0la \u00a0Ley \u00a0906 \u00a0de \u00a02004, \u00a0es \u00a0facultad \u00a0del demandante elevar \u00a0petici\u00f3n de insistencia en relaci\u00f3n con lo decidido. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese y c\u00famplase \u00a0<\/p>\n<p>MAR\u00cdA \u00a0DEL \u00a0ROSARIO \u00a0GONZ\u00c1LEZ DE LEMOS \u00a0\u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SIGIFREDO ESPINOSA P\u00c9REZ \u00a0\u00a0<\/p>\n<p>ALFREDO \u00a0 G\u00d3MEZ \u00a0 QUINTERO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0AUGUSTO J. IB\u00c1\u00d1EZ GUZM\u00c1N \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JORGE \u00a0LUIS \u00a0QUINTERO MILAN\u00c9S\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0YESID RAM\u00cdREZ BASTIDAS \u00a0\u00a0<\/p>\n<p>JULIO \u00a0ENRIQUE \u00a0SOCHA \u00a0SALAMANCA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JAVIER \u00a0 \u00a0 \u00a0ZAPATA \u00a0ORTIZ \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p>1 Folio 32 del cuaderno del Tribunal. \u00a0\u00a0<\/p>\n<p>2 Folio 18 ib\u00eddem. \u00a0\u00a0<\/p>\n<p>3 Folios 17-18 ib\u00eddem. \u00a0\u00a0<\/p>\n<p>4 \u00a0 Sentencia \u00a0 de \u00a0 12 \u00a0 de \u00a0 diciembre \u00a0 de \u00a0 2005, \u00a0 radicaci\u00f3n \u00a024322. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso n.\u00ba 34398 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Magistrado Ponente \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0JULIO ENRIQUE SOCHA SALAMANCA \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-21245","post","type-post","status-publish","format-standard","hentry","category-18"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/21245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=21245"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/21245\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=21245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=21245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=21245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}