{"id":20350,"date":"2023-09-11T22:52:54","date_gmt":"2023-09-11T22:52:54","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3242017-06-10\/"},"modified":"2023-09-11T22:52:54","modified_gmt":"2023-09-11T22:52:54","slug":"3242017-06-10","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3242017-06-10\/","title":{"rendered":"32420(17-06-10)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso n.\u00ba 32420 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado ponente: \u00a0<\/p>\n<p>YESID \u00a0 \u00a0RAM\u00cdREZ \u00a0BASTIDAS \u00a0\u00a0<\/p>\n<p>Aprobado Acta N\u00b0190 \u00a0<\/p>\n<p>Bogot\u00e1, D. C., junio diecisiete (17) de dos \u00a0mil diez (2010). \u00a0\u00a0<\/p>\n<p>VISTOS: \u00a0<\/p>\n<p>Se procede a resolver sobre la admisibilidad \u00a0de \u00a0la \u00a0demanda de casaci\u00f3n presentada por el defensor de Harold Hermel Burbano \u00a0Eraso, \u00a0contra \u00a0la \u00a0sentencia del Tribunal de Pasto que confirm\u00f3 la del Juzgado \u00a0Promiscuo \u00a0del \u00a0Circuito \u00a0de \u00a0Samaniego, \u00a0mediante la cual se le conden\u00f3 por el \u00a0delito de acceso carnal violento tentado. \u00a0\u00a0<\/p>\n<p>HECHOS Y ACTUACI\u00d3N PROCESAL: \u00a0<\/p>\n<p>1.- Los primeros fueron tratados en el fallo \u00a0impugnado de la siguiente manera: \u00a0\u00a0<\/p>\n<p>Sucedieron \u00a0en \u00a0las \u00a0horas de la ma\u00f1ana del \u00a0d\u00eda \u00a0lunes \u00a02 \u00a0de \u00a0octubre \u00a0de \u00a02000, \u00a0en \u00a0la \u00a0casa \u00a0de habitaci\u00f3n de la menor \u00a0L.M.C.S.1, \u00a0quien contaba con 13 a\u00f1os de edad (naci\u00f3 el 30 de septiembre de \u00a01987), \u00a0ubicada en la vereda Taconal del Municipio de Cumbitara (Nari\u00f1o), donde \u00a0se \u00a0encontraba \u00a0sola \u00a0realizando \u00a0labores del hogar, momento que fue aprovechado \u00a0por \u00a0el \u00a0procesado \u00a0Harold \u00a0Hermel \u00a0Burbano \u00a0Eraso \u00a0para seducirla, como no tuvo \u00a0\u00e9xito, \u00a0la \u00a0tom\u00f3 \u00a0con \u00a0fuerza \u00a0por la cintura y la condujo hasta la cama de su \u00a0madre, \u00a0en \u00a0cuyo \u00a0lugar \u00a0sin \u00a0su consentimiento o contra su voluntad le baj\u00f3 el \u00a0pantal\u00f3n \u00a0y \u00a0el \u00a0interior, \u00a0haciendo \u00a0\u00e9l \u00a0lo \u00a0mismo con sus prendas de vestir, \u00a0previo \u00a0el \u00a0manoseo \u00a0de \u00a0sus senos y vagina, comenz\u00f3 la refriega para accederla \u00a0carnalmente, \u00a0no \u00a0consumando \u00a0tal \u00a0acto, \u00a0por \u00a0haber \u00a0sido \u00a0sorprendido \u00a0por \u00a0el \u00a0padrastro \u00a0 de \u00a0 aquella \u00a0 menor, \u00a0 el \u00a0se\u00f1or \u00a0(\u2026) \u00a0quien \u00a0le \u00a0reproch\u00f3 \u00a0tal \u00a0proceder. \u00a0\u00a0<\/p>\n<p>2.- \u00a0Abierta \u00a0la \u00a0investigaci\u00f3n y vinculado \u00a0legalmente \u00a0mediante \u00a0indagatoria \u00a0Harold \u00a0Hermel Burbano Eraso, la Fiscal\u00eda 47 \u00a0Delegada \u00a0Seccional \u00a0mediante resoluci\u00f3n del 17 de noviembre de 2005 dispuso en \u00a0su \u00a0contra \u00a0medida \u00a0de \u00a0aseguramiento \u00a0consistente \u00a0en detenci\u00f3n preventiva sin \u00a0derecho \u00a0a libertad provisional, como presunto autor del delito de acceso carnal \u00a0violento en la modalidad de tentativa. \u00a0\u00a0<\/p>\n<p>3.- \u00a0Cerrada \u00a0la \u00a0instrucci\u00f3n, \u00a0la \u00a0misma \u00a0Fiscal\u00eda \u00a0el \u00a027 de noviembre de 2006 profiri\u00f3 resoluci\u00f3n de acusaci\u00f3n en su \u00a0contra, \u00a0por \u00a0la \u00a0conducta \u00a0punible \u00a0atribuida \u00a0al \u00a0momento de la definici\u00f3n de \u00a0situaci\u00f3n \u00a0jur\u00eddica, \u00a0decisi\u00f3n que alcanz\u00f3 ejecutoria el 28 de mayo de 2007, \u00a0cuando la Fiscal\u00eda Delegada ante el Tribunal la confirm\u00f3. \u00a0\u00a0<\/p>\n<p>4.- \u00a0Correspondi\u00f3 \u00a0al Juzgado Promiscuo del \u00a0Circuito \u00a0 de \u00a0Samaniego \u00a0adelantar \u00a0el \u00a0juicio \u00a0y \u00a0celebrada \u00a0la \u00a0audiencia \u00a0de \u00a0juzgamiento, \u00a0el 7 de diciembre de 2007 conden\u00f3 a Harold Hermel Burbano Eraso a \u00a0las \u00a0penas \u00a0de \u00a0cincuenta \u00a0y \u00a0cinco \u00a0(55) \u00a0meses \u00a0de \u00a0prisi\u00f3n, interdicci\u00f3n de \u00a0derechos \u00a0y \u00a0funciones p\u00fablicas por tiempo igual, al pago de perjuicios morales \u00a0en \u00a0suma \u00a0equivalente \u00a0a \u00a0veinte \u00a0(20) salarios m\u00ednimos legales mensuales, y le \u00a0neg\u00f3 \u00a0la \u00a0suspensi\u00f3n \u00a0condicional \u00a0de \u00a0la ejecuci\u00f3n de la pena como autor del \u00a0delito de acceso carnal violento en modalidad de tentativa. \u00a0\u00a0<\/p>\n<p>5.- \u00a0La providencia anterior fue apelada por \u00a0el \u00a0defensor \u00a0y \u00a0el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Pasto \u00a0el \u00a025 de febrero de 2009 la \u00a0confirm\u00f3. \u00a0\u00a0<\/p>\n<p>6.- \u00a0El \u00a0fallo \u00a0de \u00a0segundo grado objeto del \u00a0recurso de casaci\u00f3n se interpuso por la defensa del procesado. \u00a0\u00a0<\/p>\n<p>LA DEMANDA: \u00a0<\/p>\n<p>Al amparo de la causal tercera del art\u00edculo \u00a0207 \u00a0 de \u00a0 la \u00a0 ley \u00a0 600 \u00a0 de \u00a0 2000, \u00a0el \u00a0impugnante \u00a0formul\u00f3 \u00a0dos \u00a0censuras, \u00a0as\u00ed: \u00a0\u00a0<\/p>\n<p>1.- \u00a0En \u00a0el \u00a0cargo \u00a0primero \u00a0acus\u00f3 \u00a0que \u00a0la sentencia se halla viciada al \u00a0haberse \u00a0calificado como acceso carnal violento tentado y no como \u201cacto sexual \u00a0abusivo\u201d \u00a0en \u00a0la \u00a0forma \u00a0como \u00a0lo \u00a0denomin\u00f3 el Juzgado Promiscuo Municipal de \u00a0Cumbitara cuando avoc\u00f3 la apertura de investigaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Adujo que de los testimonios de la menor y su \u00a0padrastro \u00a0se \u00a0puede \u00a0inferir \u00a0que \u00a0los hechos no se adecuan al delito de acceso \u00a0carnal \u00a0violento \u00a0en \u00a0modalidad \u00a0de tentativa sino al de acto sexual abusivo con \u00a0menor \u00a0de \u00a0catorce a\u00f1os del art\u00edculo 305 del Decreto Ley 100 de 1980, toda vez \u00a0que \u00a0ocurrieron \u00a0antes \u00a0del \u00a025 de julio de 2001, pues la circunstancia de haber \u00a0visto \u00a0al \u00a0acusado \u00a0desnudo \u00a0\u201ccon el miembro viril expuesto\u201d permite deducir \u00a0que \u00a0la intenci\u00f3n de \u00e9ste no era la de penetrar a la ni\u00f1a sino que se trataba \u00a0de \u00a0expresiones \u00a0de \u00a0erotismo, m\u00e1xime cuando lo dicho por aquella en sentido de \u00a0que \u00a0Burbano \u00a0Eraso \u00a0\u201cle \u00a0meti\u00f3 la mano en la vagina\u201d no encuentra respaldo \u00a0probatorio, \u00a0de \u00a0donde \u00a0infiere \u00a0que \u00a0ella \u00a0confundi\u00f3 \u00a0la introducci\u00f3n con los \u00a0tocamientos, \u00a0error \u00a0en \u00a0el \u00a0que \u00a0de \u00a0igual \u00a0se \u00a0incurri\u00f3 en el fallo de primer \u00a0grado. \u00a0\u00a0<\/p>\n<p>Manifest\u00f3 \u00a0que \u00a0las \u00a0imputaciones deben ser \u00a0concordantes \u00a0en \u00a0lo \u00a0f\u00e1ctico \u00a0y \u00a0jur\u00eddico, \u00a0y de esa manera se hace necesario \u00a0\u201cretrotraer \u00a0la \u00a0actuaci\u00f3n \u00a0al \u00a0momento \u00a0de \u00a0la \u00a0indagatoria\u201d \u00a0para \u00a0que al \u00a0procesado \u00a0se \u00a0le haga una debida atribuci\u00f3n y respete de esa manera el derecho \u00a0de \u00a0defensa \u00a0que en la actuaci\u00f3n fue objeto de menoscabo porque a Burbano Eraso \u00a0se le imput\u00f3 un tipo que no corresponde con lo acontecido. \u00a0\u00a0<\/p>\n<p>Refiri\u00f3 \u00a0lo \u00a0narrado \u00a0por \u00a0la \u00a0menor cuando \u00a0manifest\u00f3 que: \u00a0\u00a0<\/p>\n<p>Burbano Eraso pretendi\u00f3 abrazarme y besarme \u00a0y \u00a0me \u00a0llev\u00f3 \u00a0a la cama y de la fuerza se sali\u00f3 el bot\u00f3n del pantal\u00f3n y tras \u00a0fuerte \u00a0lucha me baj\u00f3 los pantalones y el interior hasta las rodillas y el hizo \u00a0lo \u00a0mismo con sus pantalones e interior y en ese preciso momento volvi\u00f3 (\u2026) y \u00a0yo grite. \u00a0\u00a0<\/p>\n<p>Adujo que de lo as\u00ed narrado se puede inferir \u00a0que \u00a0esas \u00a0acciones \u00a0no tuvieron la entidad de un acceso carnal tentado, sino de \u00a0actos \u00a0 sexuales \u00a0diferentes \u00a0a \u00a0realizarse \u00a0en \u00a0la \u00a0cama \u00a0en \u00a0b\u00fasqueda \u00a0de \u00a0la \u00a0desnudez. \u00a0\u00a0<\/p>\n<p>Manifest\u00f3 \u00a0que indicativo de lo anterior es \u00a0que \u00a0Burbano \u00a0Eraso compareci\u00f3 de manera pac\u00edfica y sin temores al llamado que \u00a0le \u00a0hizo \u00a0la \u00a0justicia, de donde infiere que \u00e9ste ten\u00eda la convicci\u00f3n interna \u00a0de \u00a0responder \u00a0por \u00a0un \u00a0hecho \u00a0\u201cde menor car\u00e1cter\u201d que el de la violaci\u00f3n, \u00a0pues fueron \u201cactos consentidos\u201d. \u00a0\u00a0<\/p>\n<p>Argument\u00f3 \u00a0que lo narrado por la menor como \u00a0agregado \u00a0en sentido de que aqu\u00e9l intent\u00f3 introducirle sus dedos en la vagina, \u00a0fue \u00a0una \u00a0circunstancia \u00a0que \u00a0no \u00a0se \u00a0le \u00a0puso \u00a0de \u00a0presente en la diligencia de \u00a0indagatoria \u00a0y \u00a0que \u00a0era necesario hacerlo de acuerdo con el art\u00edculo 338 de la \u00a0ley 600 de 2000. \u00a0\u00a0<\/p>\n<p>Por lo anterior, solicit\u00f3 a la Sala decretar \u00a0la \u00a0nulidad \u00a0de lo actuado hasta la versi\u00f3n inclusive que rindi\u00f3 Burbano Eraso \u00a0ante \u00a0el Juez Promiscuo Municipal de Cumbitara, para que se repita la actuaci\u00f3n \u00a0en t\u00e9rminos de estricta legalidad. \u00a0\u00a0<\/p>\n<p>2.- \u00a0En \u00a0el \u00a0cargo \u00a0segundo \u00a0acus\u00f3 \u00a0que \u00a0la \u00a0sentencia \u00a0se \u00a0halla viciada \u00a0porque \u00a0las \u00a0pruebas solicitadas por la defensa no se practicaron, raz\u00f3n por la \u00a0que infiere se desconoci\u00f3 el postulado de investigaci\u00f3n integral. \u00a0\u00a0<\/p>\n<p>Refiri\u00f3 \u00a0que \u00a0a \u00a0la \u00a0actuaci\u00f3n \u00a0arrib\u00f3 un \u00a0documento \u00a0mediante \u00a0el \u00a0cual \u00a0la menor y su madre con la aceptaci\u00f3n de Burbano \u00a0Eraso, \u00a0se \u00a0retractaron \u00a0de \u00a0los \u00a0hechos \u00a0iniciales, \u00a0actitud \u00a0que \u00a0de igual fue \u00a0adoptada \u00a0por \u00a0el \u00a0padrastro \u00a0en \u00a0ampliaci\u00f3n de testimonio. Consider\u00f3 que esos \u00a0cambios \u00a0al constituirse \u201cen descr\u00e9dito\u201d de la prueba de cargo, necesitaban \u00a0cotejarse \u00a0para \u00a0arribar con mayor solidez a la certeza, ejercicio en el cual se \u00a0debi\u00f3 \u00a0incluir \u00a0al abogado Jhon Jairo Ram\u00edrez Caicedo, Personero del Municipio \u00a0de \u00a0Cumbitara \u00a0quien elabor\u00f3 ese medio de convicci\u00f3n, para confrontarlo acerca \u00a0de \u00a0si lo consignado en el mismo proven\u00eda de la voluntad e inter\u00e9s de aquellas \u00a0o \u00a0de \u00a0Burbano \u00a0Eraso, \u00a0lo \u00a0cual \u00a0no \u00a0se \u00a0hizo, omisi\u00f3n que afect\u00f3 el deber de \u00a0investigar lo favorable y desfavorable al sindicado. \u00a0\u00a0<\/p>\n<p>Consider\u00f3 \u00a0que \u00a0de \u00a0haberse \u00a0esclarecido lo \u00a0anterior \u00a0se \u00a0habr\u00eda podido acreditar que \u201ctodo obedeci\u00f3 a una orquestaci\u00f3n \u00a0de \u00a0parte \u00a0de \u00a0la \u00a0madre \u00a0de \u00a0la \u00a0menor \u00a0para obtener beneficios econ\u00f3micos\u201d, \u00a0conclusi\u00f3n \u00a0que \u00a0a \u00a0su \u00a0juicio \u00a0\u201cse \u00a0qued\u00f3 \u00a0en \u00a0la duda\u201d por las omisiones \u00a0vistas. \u00a0\u00a0<\/p>\n<p>Por lo anterior, solicit\u00f3 a la Sala \u201ccasar \u00a0la \u00a0sentencia\u201d \u00a0y \u00a0decretar \u00a0la \u00a0nulidad \u00a0de lo actuado a partir del cierre de \u00a0investigaci\u00f3n inclusive. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA CORTE: \u00a0<\/p>\n<p>1.- \u00a0El \u00a0recurso extraordinario de casaci\u00f3n \u00a0entendido \u00a0como \u00a0control \u00a0de \u00a0constitucionalidad \u00a0y \u00a0legalidad de las sentencias \u00a0proferidas \u00a0en \u00a0segundo \u00a0grado \u00a0se \u00a0halla \u00a0des-formalizado \u00a0en lo relativo a las \u00a0exigencias \u00a0 rigurosas \u00a0de \u00a0debida \u00a0t\u00e9cnica \u00a0que \u00a0en \u00a0el \u00a0pasado \u00a0inmediato \u00a0se \u00a0demandaban, \u00a0a las que en el presente no se les debe otorgar preponderancia pues \u00a0ello \u00a0implicar\u00eda \u00a0contrariar \u00a0el \u00a0principio constitucional de prevalencia de lo \u00a0sustancial, \u00a0en \u00a0la \u00a0medida \u00a0que \u00a0los controles de referencia no recaen sobre lo \u00a0formalmente \u00a0demandado \u00a0sino \u00a0sobre \u00a0el \u00a0proceso \u00a0en \u00a0s\u00ed \u00a0y \u00a0lo decidido en las \u00a0instancias. \u00a0\u00a0<\/p>\n<p>El anterior postulado se debe hacer extensivo \u00a0incluso \u00a0para \u00a0las \u00a0impugnaciones \u00a0que \u00a0se \u00a0efect\u00faen \u00a0contra \u00a0las sentencias de \u00a0segundo \u00a0 grado \u00a0proferidas \u00a0en \u00a0vigencia \u00a0de \u00a0la \u00a0Ley \u00a0600 \u00a0de \u00a02000, \u00a0pero \u00a0la \u00a0des-formalizaci\u00f3n \u00a0no \u00a0convierte \u00a0a la casaci\u00f3n penal en una tercera instancia \u00a0para \u00a0prolongar \u00a0en \u00a0libre discurso los debates dados en los fallos de instancia \u00a0sobre \u00a0unas presuntos vicios por err\u00f3nea calificaci\u00f3n y menoscabo al postulado \u00a0de \u00a0 investigaci\u00f3n \u00a0 integral, \u00a0 aspectos \u00a0que \u00a0de \u00a0manera \u00a0concreta \u00a0pero \u00a0sin \u00a0trascendencia se plantearon en la demanda. \u00a0\u00a0<\/p>\n<p>En \u00a0esta \u00a0sede extraordinaria a efecto de la \u00a0prosperidad \u00a0de \u00a0los \u00a0cargos antes que exigencias formales de debida t\u00e9cnica lo \u00a0que \u00a0se demandan son requerimientos l\u00f3gicos y jur\u00eddicos que sean desarrollados \u00a0con \u00a0razones \u00a0suficientes \u00a0en la finalidad de evidenciar a la Corte con efectiva \u00a0trascendencia \u00a0 sustancial \u00a0 que \u00a0 la \u00a0 declaraci\u00f3n \u00a0 de \u00a0 justicia \u00a0objeto \u00a0de \u00a0impugnaci\u00f3n, \u00a0la \u00a0cual \u00a0llega \u00a0a \u00a0esta \u00a0sede \u00a0extraordinaria \u00a0amparada \u00a0por \u00a0el \u00a0principio \u00a0de \u00a0la \u00a0doble \u00a0unidad jur\u00eddica de decisi\u00f3n, se fund\u00f3 en errores de \u00a0hecho \u00a0o \u00a0de derecho manifiestos o se profiri\u00f3 al interior de un juicio viciado \u00a0por \u00a0irregularidades \u00a0que \u00a0afectaron \u00a0la \u00a0estructura \u00a0o \u00a0la garant\u00eda del debido \u00a0proceso \u00a0o \u00a0del \u00a0derecho \u00a0de \u00a0defensa, \u00a0errores \u00a0in \u00a0iudicando \u00a0o \u00a0in procedendo \u00a0claramente \u00a0 diferenciados \u00a0 en \u00a0sus \u00a0realidades \u00a0y \u00a0alcances \u00a0que \u00a0reclaman \u00a0el \u00a0correspondiente \u00a0control \u00a0legal \u00a0o \u00a0constitucional \u00a0y los necesarios correctivos \u00a0sustanciales o procesales de que se trate. \u00a0\u00a0<\/p>\n<p>2.- \u00a0Por \u00a0tanto, \u00a0cuando \u00a0en \u00a0la \u00a0demanda de \u00a0casaci\u00f3n \u00a0 se\u00a0 \u00a0 omiten \u00a0las \u00a0exigencias \u00a0relacionadas \u00a0con \u00a0una \u00a0adecuada \u00a0formulaci\u00f3n \u00a0del \u00a0cargo \u00a0y se deja de se\u00f1alar con claridad y precisi\u00f3n debida \u00a0sus \u00a0fundamentos o cuando lo acusado se queda en el plano de los enunciados como \u00a0aqu\u00ed \u00a0ha ocurrido sin demostraci\u00f3n ni incidencias reales de infirmaci\u00f3n ni de \u00a0mutaci\u00f3n \u00a0sustancial total o parcial de lo resuelto en la segunda instancia, la \u00a0consecuencia \u00a0procesal \u00a0inmediata \u00a0no \u00a0puede \u00a0ser otra que la inadmisi\u00f3n seg\u00fan \u00a0as\u00ed lo estatuye el art\u00edculo 213\u00a0 de la Ley 600 de 2000. \u00a0\u00a0<\/p>\n<p>3.- \u00a0Las siguientes son las falencias que se \u00a0advierten \u00a0en \u00a0la \u00a0impugnaci\u00f3n \u00a0presentada \u00a0por \u00a0el \u00a0defensor \u00a0de Harold Hermel \u00a0Burbano Eraso. \u00a0\u00a0<\/p>\n<p>3.1.- \u00a0El \u00a0cargo \u00a0primero \u00a0mediante \u00a0el \u00a0cual acus\u00f3 que la sentencia se \u00a0encuentra \u00a0viciada \u00a0por \u00a0err\u00f3nea \u00a0calificaci\u00f3n porque la conducta atribuida al \u00a0acusado \u00a0no \u00a0se \u00a0adecuaba al delito de acceso carnal violento tentado sino al de \u00a0acto \u00a0sexual \u00a0abusivo \u00a0con menor de catorce a\u00f1os, no tiene vocaci\u00f3n de \u00e9xito, \u00a0toda \u00a0vez que la presunta irregularidad enunciada se formul\u00f3 en libre discurso, \u00a0valga \u00a0decir, \u00a0anteponiendo \u00a0el \u00a0casacionista \u00a0su \u00a0particular valoraci\u00f3n de los \u00a0hechos a la forma como la hicieron los jueces de instancia. \u00a0\u00a0<\/p>\n<p>El \u00a0 error \u00a0 en \u00a0la \u00a0denominaci\u00f3n \u00a0de \u00a0la \u00a0infracci\u00f3n \u00a0se consolida cuando el comportamiento se lo ubica en un nomen iuris \u00a0o \u00a0nombre gen\u00e9rico distinto del que le corresponde, esto es, cuando se halla en \u00a0un \u00a0t\u00edtulo o cap\u00edtulo diferente del imputado en la resoluci\u00f3n de acusaci\u00f3n y \u00a0derivado \u00a0en \u00a0el fallo, en cuyo evento su demostraci\u00f3n debe darse por la causal \u00a0tercera \u00a0pero bajo los \u00e1mbitos de la causal primera del art\u00edculo 207 de la ley \u00a0600 \u00a0de \u00a02000 \u00a0demostrando que los jueces de instancia incurrieron en errores de \u00a0hecho \u00a0 \u00a0o \u00a0 \u00a0derecho, \u00a0 \u00a0criterio \u00a0 \u00a0metodol\u00f3gico \u00a0 \u00a0que \u00a0 \u00a0el \u00a0 \u00a0casacionista \u00a0desatendi\u00f3. \u00a0\u00a0<\/p>\n<p>De \u00a0otra \u00a0parte, \u00a0desde \u00a0la \u00a0prevalencia del \u00a0derecho \u00a0sustancial \u00a0no \u00a0se \u00a0observa \u00a0equ\u00edvocos \u00a0de \u00a0adecuaci\u00f3n en nomen iuris \u00a0diferente, \u00a0pues \u00a0cuando \u00a0la \u00a0menor \u00a0denunci\u00f3 \u00a0los \u00a0hechos, \u00a0de \u00a0manera puntual \u00a0dijo: \u00a0\u00a0<\/p>\n<p>El d\u00eda lunes dos de octubre (\u2026) lleg\u00f3 el \u00a0se\u00f1or \u00a0Harold \u00a0Burbano \u00a0Eraso \u00a0y dijo: \u201cbuenos d\u00edas\u201d y pregunt\u00f3 si estaba \u00a0(\u2026) \u00a0y mi madre, yo le dije que mi madre estaba adentro y don (\u2026) trabajando \u00a0en \u00a0la \u00a0huerta \u00a0pero \u00a0no \u00a0me \u00a0crey\u00f3 \u00a0y entr\u00f3 abusivamente a la pieza y como yo \u00a0estaba \u00a0en \u00a0la \u00a0cocina lavando loza me sal\u00ed al patio, y \u00e9l me sigui\u00f3 y trat\u00f3 \u00a0de \u00a0abrazarme y besarme, por ello le dije que me dejara ya que es casado y tiene \u00a0hijos \u00a0y \u00a0me agarr\u00e9 de la cerca para que no me llevara, ya que me agarr\u00f3 de la \u00a0cintura \u00a0y \u00a0me hizo cosquillas para que me soltara, despu\u00e9s de un rato de lucha \u00a0me \u00a0gan\u00f3 \u00a0y \u00a0abrazado de la cintura me llev\u00f3 a la pieza y me tir\u00f3 de la cama, \u00a0sigui\u00f3 \u00a0con \u00a0los \u00a0pantalones, \u00a0me los jalaba dur\u00edsimo, pero como yo los ten\u00eda \u00a0agarrados \u00a0no \u00a0me \u00a0los \u00a0pod\u00eda \u00a0bajar \u00a0y de la fuerza se le sali\u00f3 el bot\u00f3n del \u00a0pantal\u00f3n \u00a0y \u00a0tras \u00a0fuerte lucha me baj\u00f3 los pantalones y el interior hasta las \u00a0rodillas \u00a0y \u00a0\u00e9l \u00a0hizo \u00a0lo \u00a0mismo con sus pantalones e interior y es ese preciso \u00a0momento \u00a0volvi\u00f3 \u00a0(\u2026) \u00a0y yo grit\u00e9: \u201c(\u2026) ven\u00ed a favorecerme que me est\u00e1n \u00a0forcejeando\u201d. \u00a0\u00a0<\/p>\n<p>En declaraci\u00f3n rendida el 1 de octubre de \u00a02002, ratific\u00f3 lo denunciado as\u00ed: \u00a0\u00a0<\/p>\n<p>Si \u00a0me \u00a0ratifico en mi denuncia en contra de \u00a0ese \u00a0se\u00f1or. \u00a0Yo \u00a0le mir\u00e9 el miembro de ese hombre lo ten\u00eda erecto y se subi\u00f3 \u00a0encima \u00a0de \u00a0mi cuerpo cuando ya me hab\u00eda bajado el pantal\u00f3n hasta las rodillas \u00a0y \u00a0tambi\u00e9n mi interior y quiso meter el miembro de \u00e9l en mi vaina, yo alcanc\u00e9 \u00a0a \u00a0sentirlo \u00a0en mis piernas y lo ten\u00eda parado, yo trataba de moverme y ajustaba \u00a0las \u00a0piernas \u00a0para \u00a0que \u00a0no me viole, pas\u00f3 harto tiempo de lo que empez\u00f3 pas\u00f3 \u00a0como \u00a0una \u00a0media \u00a0hora, \u00a0y \u00a0cuando \u00a0ya me arranc\u00f3 el bot\u00f3n de un bluyin que yo \u00a0ten\u00eda \u00a0puesto \u00a0y \u00a0me \u00a0baj\u00f3 \u00a0el \u00a0pantal\u00f3n \u00a0y \u00a0el \u00a0interior \u00a0y \u00a0el se baj\u00f3 los \u00a0pantalones \u00a0y su interior, \u00e9l ten\u00eda un pantal\u00f3n yin azul oscuro, del interior \u00a0no \u00a0recuerdo \u00a0que color, ten\u00eda una camiseta color gris, estuvo encima m\u00edo como \u00a0quince \u00a0minutos \u00a0forcejeando conmigo, \u00e9l no alcanz\u00f3 a derramar el semen encima \u00a0m\u00edo, \u00a0porque \u00a0lleg\u00f3 \u00a0(\u2026) \u00a0y \u00a0\u00e9l \u00a0me \u00a0defendi\u00f3 \u00a0y \u00a0ese Harold se subi\u00f3 los \u00a0pantalones \u00a0y \u00a0sali\u00f3 caminando, yo me sub\u00ed los pantalones y me fui a la cocina \u00a0a tomar agua y despu\u00e9s ya le cont\u00e9 a mi mam\u00e1 lo sucedido. \u00a0\u00a0<\/p>\n<p>En \u00a0 \u00a0igual \u00a0 \u00a0sentido \u00a0 su \u00a0 padrastro, \u00a0declar\u00f3: \u00a0\u00a0<\/p>\n<p>El \u00a0d\u00eda \u00a0lunes \u00a0dos \u00a0de octubre de dos mil, \u00a0siendo \u00a0mas \u00a0o \u00a0menos \u00a0las \u00a0ocho \u00a0de la ma\u00f1ana, en nuestra casa de habitaci\u00f3n, \u00a0rectifico \u00a0siendo \u00a0las \u00a0ocho \u00a0y \u00a0media, \u00a0me toc\u00f3 presenciar un caso inesperado, \u00a0extra\u00f1o, \u00a0y \u00a0sucedi\u00f3 \u00a0que encontr\u00e9 al se\u00f1or Harold Burbano dentro de nuestra \u00a0casa, \u00a0con \u00a0los \u00a0pantalones \u00a0en \u00a0los \u00a0pies y la ni\u00f1a ya la hab\u00eda tenido con el \u00a0pantal\u00f3n \u00a0e \u00a0interiores a la altura de la rodilla encima de la cama, en nuestra \u00a0cama, \u00a0pero cuando yo entr\u00e9 ese se\u00f1or se asust\u00f3 y a mi me dio rabia y le dije \u00a0\u201cporqu\u00e9 \u00a0hac\u00e9s \u00a0eso \u00a0con la ni\u00f1a\u201d, \u00e9l contest\u00f3 \u201cesper\u00e1te te explico, \u00a0las \u00a0cosas \u00a0no \u00a0son \u00a0como piensas\u201d y me llev\u00f3 a un camino y dijo \u201ccuando la \u00a0mujer \u00a0no \u00a0quiere \u00a0el \u00a0hombre \u00a0no \u00a0puede \u00a0y \u00a0eso fue con gusto de ella\u201d, yo le \u00a0insist\u00ed \u00a0que \u00a0eso \u00a0no \u00a0era \u00a0as\u00ed, \u00a0ya \u00a0que \u00a0apenas \u00a0la \u00a0se\u00f1orita \u00a0(\u2026) me vio \u00a0manifest\u00f3 \u00a0\u201cPablo \u00a0defend\u00e9me, \u00a0este \u00a0se\u00f1or \u00a0me \u00a0est\u00e1 forzando\u201d y por eso \u00a0mejor \u00a0que \u00a0te \u00a0vayas, \u00a0ahora \u00a0ver\u00e1s \u00a0lo \u00a0que te va a pasar le dije. \u00a0\u00a0<\/p>\n<p>Dados \u00a0as\u00ed \u00a0los hechos, no se requiere de \u00a0mayores \u00a0argumentos \u00a0para \u00a0concluir que la conducta de acceso carnal violento en \u00a0modalidad \u00a0de \u00a0tentativa \u00a0atribuida \u00a0y \u00a0derivada \u00a0en \u00a0los \u00a0fallos de instancia a \u00a0Burbano \u00a0Eraso \u00a0se \u00a0adecu\u00f3 \u00a0en debida forma, y que esas facticidades no estaban \u00a0encaminadas \u00a0a \u00a0protagonizar \u00a0\u201cescenas \u00a0de \u00a0erotismo consentidos en la cama en \u00a0b\u00fasqueda \u00a0 de \u00a0 la \u00a0 desnudez\u201d, \u00a0esto \u00a0es, \u00a0actos \u00a0sexuales \u00a0diversos \u00a0y \u00a0sin \u00a0penetraci\u00f3n, \u00a0como \u00a0fueron \u00a0las \u00a0ligeras \u00a0conclusiones \u00a0a \u00a0las \u00a0que \u00a0arrib\u00f3 el \u00a0casacionista. \u00a0\u00a0<\/p>\n<p>De otra parte, d\u00edgase que para efectos de la \u00a0imputaci\u00f3n \u00a0f\u00e1ctica \u00a0y \u00a0jur\u00eddica de la resoluci\u00f3n de acusaci\u00f3n referida, no \u00a0era \u00a0necesario \u00a0ampliar \u00a0la \u00a0indagatoria \u00a0por \u00a0las \u00a0razones \u00a0a \u00a0las que alude el \u00a0casacionista, \u00a0pues \u00a0lo \u00a0determinante \u00a0para \u00a0arribar a esa conclusi\u00f3n no estuvo \u00a0dado \u00a0en \u00a0el \u00a0intento del procesado de manosear las partes \u00edntimas de la menor, \u00a0sino \u00a0el contexto general descrito por aquella, razones m\u00e1s que suficientes por \u00a0las que lo as\u00ed censurado se inadmite. \u00a0\u00a0<\/p>\n<p>3.2.- \u00a0 \u00a0 \u00a0El \u00a0 \u00a0 cargo \u00a0 segundo \u00a0mediante el cual acus\u00f3 que la actuaci\u00f3n se encuentra \u00a0viciada \u00a0por \u00a0menoscabo \u00a0del \u00a0principio \u00a0de investigaci\u00f3n integral porque no se \u00a0llam\u00f3 \u00a0en \u00a0ampliaci\u00f3n \u00a0de \u00a0testimonio \u00a0a \u00a0la \u00a0menor \u00a0y \u00a0a \u00a0su madre quienes se \u00a0retractaron \u00a0 a \u00a0trav\u00e9s \u00a0de \u00a0un \u00a0documento, \u00a0y \u00a0era \u00a0necesario \u00a0\u201ccotejar \u00a0sus \u00a0afirmaciones \u00a0para arribar a la certeza y no dejar la investigaci\u00f3n en el plano \u00a0de la duda\u201d, no tiene vocaci\u00f3n de existo. En efecto: \u00a0\u00a0<\/p>\n<p>El \u00a0principio \u00a0de \u00a0investigaci\u00f3n \u00a0integral \u00a0tratado \u00a0 \u00a0 \u00a0por \u00a0 \u00a0 \u00a0el \u00a0 \u00a0 \u00a0art\u00edculo \u00a0 \u00a0 \u00a0202 \u00a0\u00a0<\/p>\n<p>de la Ley 600 de \u00a02000 \u00a0 que \u00a0 a \u00a0 su \u00a0 vez \u00a0es \u00a0desarrollado \u00a0por \u00a0el \u00a0art\u00edculo \u00a02343 \u00a0ejusdem, \u00a0es \u00a0uno, \u00a0entre \u00a0otros, \u00a0de los \u00a0postulados \u00a0que integran la categor\u00eda jur\u00eddica general de debido proceso penal \u00a0entendido \u00a0este \u00a0como \u00a0un proceso de conocimiento y determinaci\u00f3n de una verdad \u00a0concreta referida a un delito en especial. \u00a0\u00a0<\/p>\n<p>En esa medida, en la b\u00fasqueda de la verdad \u00a0singular \u00a0dada \u00a0\u00e9sta \u00a0como \u00a0un \u00a0proceso \u00a0de \u00a0trayectoria \u00a0y \u00a0resultados se hace \u00a0necesario \u00a0que \u00a0el \u00a0funcionario \u00a0por \u00a0obligaci\u00f3n y de acuerdo con los t\u00e9rminos \u00a0vinculantes \u00a0del \u00a0art\u00edculo 20 en cita se ocupe de investigar tanto lo favorable \u00a0como \u00a0lo \u00a0desfavorable \u00a0respecto \u00a0de los objetos de conocimiento de que trata el \u00a0art\u00edculo 331 ib\u00eddem. \u00a0\u00a0<\/p>\n<p>Los \u00a0objetos de esclarecimiento respecto de \u00a0un \u00a0injusto \u00a0penal \u00a0especial, tienen como referentes la determinaci\u00f3n acerca de \u00a0qui\u00e9n \u00a0o \u00a0qui\u00e9nes son los autores, part\u00edcipes, cu\u00e1les los motivos y factores \u00a0que \u00a0influyeron \u00a0en \u00a0la \u00a0violaci\u00f3n \u00a0de \u00a0la \u00a0ley \u00a0sustantiva, las circunstancias \u00a0modales \u00a0 \u00a0y \u00a0 temporales, \u00a0 las \u00a0 condiciones \u00a0 sociales \u00a0 y \u00a0 los \u00a0 da\u00f1os \u00a0 y \u00a0perjuicios. \u00a0\u00a0<\/p>\n<p>A\u00fan \u00a0cuando \u00a0en \u00a0la \u00a0investigaci\u00f3n de las \u00a0conductas \u00a0punibles \u00a0no \u00a0hay reglas r\u00edgidas sino que por el contrario existe la \u00a0libertad \u00a0probatoria \u00a0que \u00a0en todo evento se liga al principio heur\u00edstico de la \u00a0verificabilidad, \u00a0se \u00a0ha \u00a0considerado \u00a0por la jurisprudencia de esta Sala que el \u00a0postulado \u00a0de investigaci\u00f3n integral sufre menoscabo cuando existiendo soportes \u00a0materiales \u00a0pertinentes \u00a0y conducentes en orden a la determinaci\u00f3n de la verdad \u00a0el \u00a0funcionario \u00a0en \u00a0detrimento \u00a0de la facultad oficiosa o en desconocimiento de \u00a0las \u00a0peticiones \u00a0de \u00a0prueba \u00a0de \u00a0alguno de los sujetos procesales, incluidas las \u00a0citas \u00a0que \u00a0hubiera \u00a0hecho \u00a0el \u00a0sindicado \u00a0en \u00a0la \u00a0indagatoria, \u00a0no \u00a0se \u00a0hubiere \u00a0interesado \u00a0en decretarlas ni practicarlas, en la medida que de haberse allegado \u00a0-como \u00a0posibilidad- \u00a0habr\u00edan \u00a0podido \u00a0incidir \u00a0sustancialmente en el sentido de \u00a0justicia declarado en la sentencia. \u00a0\u00a0<\/p>\n<p>En forma reiterada la Sala ha sostenido que \u00a0no \u00a0toda \u00a0omisi\u00f3n \u00a0en el decreto y pr\u00e1ctica de pruebas genera afectaci\u00f3n a la \u00a0investigaci\u00f3n \u00a0integral, \u00a0pues \u00a0para \u00a0viciar el procedimiento se hace necesario \u00a0que \u00a0esas \u00a0falencias \u00a0hubiesen \u00a0sido \u00a0trascendentes, \u00a0es decir, incidentes en la \u00a0verdad \u00a0material \u00a0declarada \u00a0y \u00a0de contera haber afectado el derecho de defensa, \u00a0que \u00a0 se \u00a0trate \u00a0de \u00a0medios \u00a0de \u00a0convicci\u00f3n \u00a0que \u00a0de \u00a0haberse \u00a0practicado \u00a0como \u00a0probabilidad \u00a0 concreta \u00a0 habr\u00edan \u00a0tenido \u00a0la \u00a0potencialidad \u00a0de \u00a0dar \u00a0un \u00a0giro \u00a0sustancial \u00a0total \u00a0o \u00a0parcial \u00a0diferente \u00a0a \u00a0los \u00a0resultados del fallo de que se \u00a0trate. \u00a0\u00a0<\/p>\n<p>Cuando \u00a0se \u00a0impugna en casaci\u00f3n penal y se \u00a0propugna \u00a0por \u00a0una \u00a0nulidad \u00a0por violaci\u00f3n al postulado en cita, corresponde al \u00a0casacionista \u00a0formular, \u00a0objetivar y demostrar que la omisi\u00f3n ya sea singular o \u00a0plural \u00a0de \u00a0pruebas \u00a0las \u00a0que habr\u00e1 de identificar, comportaba trascendencia en \u00a0los \u00a0extremos \u00a0y \u00a0contenidos \u00a0de \u00a0lo \u00a0favorable \u00a0a \u00a0la \u00a0situaci\u00f3n jur\u00eddica del \u00a0procesado \u00a0y de contera argumentar que de no haberse incurrido en esas omisiones \u00a0probatorias \u00a0las \u00a0que \u00a0eran \u00a0conducentes \u00a0por \u00a0tener \u00a0directa \u00a0relaci\u00f3n \u00a0con el \u00a0thema probandum, se habr\u00edan \u00a0podido \u00a0llegar a consolidar otros resultados como de infirmaci\u00f3n o cambio en el \u00a0grado \u00a0 de \u00a0 participaci\u00f3n \u00a0en \u00a0el \u00a0reato, \u00a0exclusi\u00f3n \u00a0o \u00a0aminoraci\u00f3n \u00a0de \u00a0la \u00a0responsabilidad \u00a0 penal \u00a0atribuida, \u00a0atenuaci\u00f3n, \u00a0degradaci\u00f3n \u00a0de \u00a0adecuaci\u00f3n \u00a0t\u00edpica \u00a0o \u00a0que \u00a0los \u00a0efectos \u00a0de \u00a0incidencia \u00a0podr\u00edan \u00a0haber \u00a0dado lugar a los \u00a0extremos de la duda probatoria. \u00a0\u00a0<\/p>\n<p>Para el evento, es cierto que en la etapa de \u00a0investigaci\u00f3n \u00a0 no \u00a0se \u00a0llam\u00f3 \u00a0en \u00a0ampliaci\u00f3n \u00a0de \u00a0testimonio \u00a0a \u00a0Jhon \u00a0Jairo \u00a0Ram\u00edrez,\u00a0 \u00a0Caicedo,\u00a0 \u00a0a \u00a0la \u00a0madre \u00a0de \u00a0la \u00a0menor \u00a0y a \u00e9sta en orden \u00a0declarar \u00a0sobre \u00a0los \u00a0contenidos del documento fechado el 10 de octubre de 2000, \u00a0que \u00a0apareci\u00f3 \u00a0a la actuaci\u00f3n cinco a\u00f1os despu\u00e9s, en el cual madre e hija se \u00a0retractaron \u00a0de \u00a0lo \u00a0afirmado \u00a0en \u00a0la \u00a0denuncia, omisi\u00f3n que fue superada en la \u00a0etapa \u00a0del \u00a0juicio \u00a0pues \u00a0aqu\u00e9l \u00a0y \u00a0la \u00a0ni\u00f1a \u00a0fueron citadas a la audiencia de \u00a0juzgamiento \u00a0pero \u00a0no \u00a0comparecieron, \u00a0sin \u00a0que \u00a0la supuesta irregularidad tenga \u00a0trascendencia \u00a0en \u00a0el \u00a0menoscabo de la ausencia de investigar lo favorable a los \u00a0intereses \u00a0Burbano \u00a0Eraso, \u00a0pues \u00a0el \u00a0juez \u00a0de \u00a0primer \u00a0grado \u00a0en \u00a0desarrollo de \u00a0ejercicios \u00a0de \u00a0sana \u00a0cr\u00edtica \u00a0efectu\u00f3 \u00a0valoraciones \u00a0al \u00a0escrito \u00a0referido \u00a0y \u00a0desestim\u00f3 los contenidos cuando sostuvo: \u00a0\u00a0<\/p>\n<p>As\u00ed las cosas, el Juzgado no est\u00e1 conforme \u00a0con \u00a0lo \u00a0argumentado \u00a0por \u00a0la defensa, como que el material probatorio recaudado \u00a0inicialmente \u00a0fue \u00a0manipulado \u00a0para favorecer los intereses del acusado, pues no \u00a0tiene \u00a0explicaci\u00f3n \u00a0alguna \u00a0que \u00a0d\u00edas \u00a0despu\u00e9s \u00a0de \u00a0acontecidos los hechos se \u00a0presente \u00a0en \u00a0la \u00a0secretar\u00eda \u00a0del \u00a0Juzgado Promiscuo Municipal de Cumbitara, un \u00a0escrito \u00a0de \u00a0desistimiento \u00a0que \u00a0no \u00a0iba a tener ning\u00fan efecto procesal, con el \u00a0auspicio \u00a0 de \u00a0varios \u00a0empleados \u00a0p\u00fablicos, \u00a0debido \u00a0al \u00a0reato \u00a0que \u00a0se \u00a0estaba \u00a0investigando, \u00a0y \u00a0por la retractaci\u00f3n del principal testigo de cargo, es decir, \u00a0el \u00a0padrastro \u00a0de \u00a0la \u00a0menor, \u00a0despu\u00e9s \u00a0de \u00a0cinco \u00a0a\u00f1os, \u00a0cuando aqu\u00e9l hab\u00eda \u00a0terminado \u00a0la \u00a0relaci\u00f3n \u00a0sentimental \u00a0que \u00a0lo \u00a0un\u00eda \u00a0con \u00a0su \u00a0madre, que no es \u00a0cre\u00edble, \u00a0debido a que no est\u00e1 acorde con lo por \u00e9l narrado d\u00edas despu\u00e9s de \u00a0acaecidos \u00a0los \u00a0hechos \u00a0investigados, \u00a0y \u00a0ser \u00a0contrario \u00a0a \u00a0lo aseverado por la \u00a0v\u00edctima, \u00a0 quien \u00a0 pese \u00a0 al \u00a0 citado \u00a0 escrito \u00a0de \u00a0desistimiento \u00a0 se \u00a0 mantuvo \u00a0 firme \u00a0 en \u00a0 su \u00a0 posici\u00f3n \u00a0 inicial, \u00a0cual \u00a0fue \u00a0el \u00a0de \u00a0haber \u00a0sido \u00a0forzada o violenta (sic) para ser \u00a0accedida \u00a0carnalmente \u00a0por \u00a0el enjuiciado, que no pudo ejecutar por el arribo de \u00a0su \u00a0padrastro \u00a0quien \u00a0la socorri\u00f3. Por tanto las pruebas recogidas inicialmente \u00a0no \u00a0han \u00a0perdido \u00a0fuerza \u00a0vinculante ni la mencionada menor acomod\u00f3 o manipul\u00f3 \u00a0los \u00a0hechos a su antojo, ni su misma madre, quiz\u00e1 por el inter\u00e9s de perjudicar \u00a0al \u00a0presunto padre (el acusado) de su hijo Eduar Yesid Solarte, cuya atestaci\u00f3n \u00a0carece \u00a0de importancia para la acreditaci\u00f3n de los hechos investigados, lo cual \u00a0no \u00a0genera \u00a0duda \u00a0de lo realmente acontecido aquella ma\u00f1ana del 2 de octubre de \u00a02000, \u00a0como \u00a0tampoco existe prueba de que \u00e9sta ejerza influencia en su pareja y \u00a0en su hija (\u2026) \u00a0\u00a0<\/p>\n<p>En este caso, como se analiz\u00f3 en la \u00faltima \u00a0ampliaci\u00f3n \u00a0de \u00a0declaraci\u00f3n, el se\u00f1or (\u2026) falt\u00f3 a la verdad, pues su dicho \u00a0no \u00a0coincide \u00a0con \u00a0lo \u00a0narrado \u00a0por \u00a0su \u00a0entenada, en esa \u00e9poca, pues cuando la \u00a0rindi\u00f3 \u00a0ya \u00a0se \u00a0hab\u00eda \u00a0separado \u00a0de su madre, todo con el fin de favorecer los \u00a0intereses \u00a0del \u00a0procesado. Lo curioso es que el escrito de desistimiento aparece \u00a0en \u00a0el \u00a0proceso \u00a0el \u00a01\u00ba \u00a0de \u00a0julio \u00a0de \u00a02005, casi a los cinco a\u00f1os de haberse \u00a0realizado \u00a0(octubre \u00a010 \u00a0de \u00a02000), \u00a0como \u00a0el \u00a0testimonio del abogado Jhon Jairo \u00a0Ram\u00edrez \u00a0Caicedo \u00a0quien \u00a0en aquella \u00e9poca fung\u00eda como Personero Municipal, lo \u00a0que \u00a0hace dudar de su atestaci\u00f3n, m\u00e1s cuando la menor y su madre en ninguno de \u00a0sus dichos hacen referencia a su intervenci\u00f3n. \u00a0\u00a0<\/p>\n<p>Al contrario de lo que sostiene la defensa, \u00a0con \u00a0el \u00a0material \u00a0probatorio \u00a0recaudado \u00a0se \u00a0establece la certeza y por ende la \u00a0convicci\u00f3n \u00a0que \u00a0el \u00a0procesado \u00a0Harold \u00a0Hermel Burbano Eraso ejerci\u00f3 violencia \u00a0sobre \u00a0la \u00a0menor \u00a0para \u00a0accederla \u00a0sexualmente, \u00a0que \u00a0no \u00a0lo \u00a0pudo \u00a0consumar por \u00a0circunstancias ajenas a su voluntad. \u00a0\u00a0<\/p>\n<p>El \u00a0ad quem, de igual forma le rest\u00f3 valor \u00a0probatorio al escrito referido en los t\u00e9rminos siguientes: \u00a0\u00a0<\/p>\n<p>Primero \u00a0no \u00a0es \u00a0cierto \u00a0que \u00a0el \u00a0documento \u00a0contenga \u00a0sellos \u00a0de \u00a0recibido \u00a0por \u00a0el despacho judicial aludido, como se puede \u00a0observar \u00a0 del \u00a0 mismo \u00a0(folio \u00a062), \u00a0lo \u00a0que \u00a0s\u00ed \u00a0existe \u00a0son \u00a0los \u00a0sellos \u00a0de \u00a0presentaci\u00f3n \u00a0personal. \u00a0Distinci\u00f3n \u00a0que debe conocer muy bien el procesado en \u00a0su \u00a0 condici\u00f3n \u00a0 de \u00a0 ex \u00a0 empleado \u00a0 judicial \u00a0 como \u00a0 lo \u00a0 manifest\u00f3 \u00a0en \u00a0su \u00a0indagatoria. \u00a0\u00a0<\/p>\n<p>Por \u00a0otra \u00a0parte, poco cre\u00edble se torna su \u00a0versi\u00f3n \u00a0sobre \u00a0la \u00a0devoluci\u00f3n \u00a0del documento por parte del despacho judicial, \u00a0con \u00a0fundamento \u00a0en \u00a0las \u00a0razones \u00a0indicadas. \u00a0Sabe \u00a0tambi\u00e9n el acusado que las \u00a0solicitudes \u00a0radicadas \u00a0ante \u00a0los \u00a0juzgados \u00a0deben \u00a0ser \u00a0resueltas oportunamente \u00a0accedi\u00e9ndose \u00a0o \u00a0no \u00a0a \u00a0lo \u00a0pedido, pero no resulta legal que se devuelva a los \u00a0firmantes \u00a0y \u00a0menos, \u00a0por \u00a0las citadas razones que desborda las funciones de los \u00a0servidores judiciales. \u00a0\u00a0<\/p>\n<p>De acuerdo con lo motivado por los jueces de \u00a0instancia \u00a0es dable colegir que sobre un documento de supuesta retractaci\u00f3n que \u00a0gener\u00f3 \u00a0dudas, pues si bien es cierto aparece fechado el 10 de octubre de 2000, \u00a0tan \u00a0s\u00f3lo \u00a0hizo \u00a0aparici\u00f3n \u00a0en la actuaci\u00f3n el 1\u00ba de julio de 2005, esto es, \u00a0cinco \u00a0a\u00f1os \u00a0despu\u00e9s \u00a0de ocurridos los hechos por incorporaci\u00f3n que del mismo \u00a0hizo \u00a0el \u00a0defensor del procesado, se infiere no es posible argumentar vicios por \u00a0menoscabo \u00a0al \u00a0postulado \u00a0de \u00a0investigaci\u00f3n integral, formulaci\u00f3n que no tiene \u00a0asidero \u00a0ni \u00a0coherencia, \u00a0pues \u00a0la madre de la menor, declar\u00f3 el 14 de marzo de \u00a02005 \u00a0y \u00a0se \u00a0ratific\u00f3, \u00a0igual lo hizo la v\u00edctima el 27 de febrero de 2001 y el \u00a01\u00ba \u00a0de \u00a0octubre de 2002 sin que en esas oportunidades se hubiesen retractado de \u00a0lo inicialmente denunciado. \u00a0\u00a0<\/p>\n<p>Como \u00a0se \u00a0dijo \u00a0el \u00a0documento \u00a0en \u00a0cita fue \u00a0incorporado \u00a0por \u00a0el \u00a0abogado defensor del procesado cinco (5) a\u00f1os despu\u00e9s de \u00a0la \u00a0supuesta \u00a0fecha \u00a0de \u00a0elaboraci\u00f3n y de manera insistente se pretendi\u00f3 hacer \u00a0valer \u00a0como medio de prueba id\u00f3neo y conducente para sacar avante los intereses \u00a0de \u00a0su \u00a0defendido, \u00a0en un comportamiento que genera sospechas. En esa medida ese \u00a0comportamiento \u00a0merece \u00a0esclarecerse \u00a0pues \u00a0no aparece di\u00e1fano, razones por las \u00a0que \u00a0se \u00a0compulsar\u00e1 \u00a0copias \u00a0a \u00a0ese \u00a0profesional \u00a0para \u00a0que \u00a0se \u00a0le \u00a0investigue \u00a0disciplinariamente \u00a0y \u00a0por \u00a0el presunto delito de fraude procesal, pues a partir \u00a0de \u00a0los \u00a0contenidos de la supuesta retractaci\u00f3n se procur\u00f3 inducir en error al \u00a0servidor p\u00fablico para que fallara a favor de Burbano Eraso. \u00a0\u00a0<\/p>\n<p>Por \u00a0 \u00a0lo \u00a0 \u00a0anterior \u00a0 el \u00a0 cargo \u00a0 se \u00a0inadmite. \u00a0\u00a0<\/p>\n<p>3.3.- Puede \u00a0afirmarse \u00a0que \u00a0los \u00a0desarrollos \u00a0de \u00a0lo \u00a0aqu\u00ed \u00a0impugnado no \u00a0convocan \u00a0ni \u00a0persuaden \u00a0a \u00a0la Corte sobre la necesidad de admitir la demanda ni \u00a0desde \u00a0la \u00a0perspectiva \u00a0oficiosa se advierte violaci\u00f3n de derechos o garant\u00edas \u00a0fundamentales \u00a0de \u00a0incidencia \u00a0sustancial \u00a0o \u00a0procesal \u00a0que permitan superar los \u00a0defectos \u00a0de lo demandado y suscitar un pronunciamiento sustitutivo de reemplazo \u00a0de absoluci\u00f3n a favor de Harold Hermel Burbano Eraso. \u00a0\u00a0<\/p>\n<p>A \u00a0m\u00e9rito de lo expuesto, la Corte Suprema \u00a0de Justicia, Sala de Casaci\u00f3n Penal, \u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1.- Inadmitir \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0por el defensor de \u00a0Harold Hermel Burbano Eraso. \u00a0\u00a0<\/p>\n<p>2.-\u00a0\u00a0\u00a0 \u00a0 \u00a0Compulsar \u00a0copias \u00a0al abogado Neyip Javier \u00a0O\u00f1ate \u00a0Paz para que se lo investigue penal y disciplinariamente por el supuesto \u00a0comportamiento de fraude procesal. \u00a0\u00a0<\/p>\n<p>3.- \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Advertir \u00a0que \u00a0contra \u00a0esta providencia no \u00a0procede ning\u00fan recurso. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0notif\u00edquese \u00a0y \u00a0devu\u00e9lvase \u00a0al \u00a0Tribunal de origen. \u00a0\u00a0<\/p>\n<p>C\u00famplase. \u00a0<\/p>\n<p>MAR\u00cdA \u00a0 DEL \u00a0 ROSARIO \u00a0 GONZ\u00c1LEZ \u00a0 DE \u00a0LEMOS \u00a0\u00a0<\/p>\n<p>JOS\u00c9 \u00a0 \u00a0 \u00a0 LEONIDAS \u00a0 \u00a0 \u00a0BUSTOS \u00a0MART\u00cdNEZ\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0SIGIFREDO ESPINOSA P\u00c9REZ \u00a0\u00a0<\/p>\n<p>ALFREDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 G\u00d3MEZ \u00a0QUINTERO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0AUGUSTO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0J. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 IB\u00c1\u00d1EZ \u00a0GUZM\u00c1N\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JORGE \u00a0 \u00a0 \u00a0 LUIS \u00a0 \u00a0 \u00a0 QUINTERO \u00a0MILAN\u00c9S\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0YESID RAM\u00cdREZ \u00a0BASTIDAS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>JULIO \u00a0 \u00a0 \u00a0 ENRIQUE \u00a0 \u00a0 \u00a0 SOCHA \u00a0SALAMANCA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JAVIER ZAPATA ORTIZ \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Secretaria \u00a0\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 \u00a0Se \u00a0omite \u00a0identificar \u00a0a \u00a0la menor y a su progenitora por respeto a su dignidad y a \u00a0su \u00a0derecho a un nombre de acuerdo con la Declaraci\u00f3n \u00a0de \u00a0los \u00a0Derechos \u00a0del \u00a0Ni\u00f1o \u00a0y en acatamiento a los \u00a0Principios \u00a0 Fundamentales \u00a0 de \u00a0Justicia \u00a0para \u00a0las \u00a0V\u00edctimas \u00a0de \u00a0Delitos \u00a0y \u00a0Abuso \u00a0de \u00a0Poder (Asamblea \u00a0General \u00a0de \u00a0la \u00a0ONU, \u00a0Resoluci\u00f3n \u00a0No \u00a040\/34 \u00a0del \u00a029 \u00a0de noviembre de 1985) al \u00a0contemplar \u00a0que \u00a0los \u00a0procedimientos \u00a0judiciales y administrativos deben adoptar \u00a0medidas \u00a0para \u00a0evitar nuevamente su victimizaci\u00f3n, en concordancia tambi\u00e9n con \u00a0lo \u00a0normado \u00a0en los art\u00edculos 47, numeral 8\u00ba; 192 y 193, numeral 7\u00ba de la ley \u00a01098 de 2006. \u00a0\u00a0<\/p>\n<p>2 Ley \u00a0600 \u00a0de \u00a02000, art\u00edculo 20.- \u201cEl funcionario judicial tiene la obligaci\u00f3n de \u00a0investigar \u00a0tanto lo favorable como lo desfavorable a los intereses del imputado \u00a0( \u00a0y \u00a0de \u00a0los \u00a0dem\u00e1s intervinientes en el proceso) (el texto en par\u00e9ntesis fue \u00a0declarado \u00a0 inexequible \u00a0 por \u00a0 la \u00a0 Corte \u00a0Constitucional \u00a0en \u00a0la \u00a0Sentencia C-760 de 2001. \u00a0\u00a0<\/p>\n<p>3 Ley \u00a0600 \u00a0de \u00a02000, \u00a0art\u00edculo 234.- \u201cImparcialidad del funcionario en la b\u00fasqueda \u00a0de \u00a0la \u00a0prueba.- \u00a0\u201cEl \u00a0funcionario \u00a0judicial \u00a0buscar\u00e1 la determinaci\u00f3n de la \u00a0verdad \u00a0real. \u00a0Para \u00a0ello \u00a0debe averiguar con igual celo, las circunstancias que \u00a0demuestren \u00a0la \u00a0existencia \u00a0de \u00a0la conducta punible, las que agraven, aten\u00faen o \u00a0exoneren \u00a0de \u00a0responsabilidad \u00a0al \u00a0procesado \u00a0y \u00a0las \u00a0que tiendan a demostrar su \u00a0inocencia\u201d \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso n.\u00ba 32420 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado ponente: \u00a0 YESID \u00a0 \u00a0RAM\u00cdREZ \u00a0BASTIDAS \u00a0\u00a0 Aprobado Acta N\u00b0190 \u00a0 Bogot\u00e1, D. C., junio diecisiete (17) de dos \u00a0mil diez (2010). \u00a0\u00a0 VISTOS: \u00a0 Se procede a resolver sobre la admisibilidad \u00a0de \u00a0la \u00a0demanda de casaci\u00f3n presentada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-20350","post","type-post","status-publish","format-standard","hentry","category-18"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/20350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=20350"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/20350\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=20350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=20350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=20350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}