{"id":19376,"date":"2023-09-11T19:46:31","date_gmt":"2023-09-11T19:46:31","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3208214-09-09\/"},"modified":"2023-09-11T19:46:31","modified_gmt":"2023-09-11T19:46:31","slug":"3208214-09-09","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3208214-09-09\/","title":{"rendered":"32082(14-09-09)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso \u00a0 \u00a0 No \u00a032082 \u00a0\u00a0<\/p>\n<p>CORTE \u00a0 SUPREMA \u00a0 DE \u00a0JUSTICIA \u00a0\u00a0<\/p>\n<p>SALA \u00a0 DE \u00a0 CASACI\u00d3N \u00a0PENAL \u00a0\u00a0<\/p>\n<p>Magistrada Ponente: \u00a0<\/p>\n<p>MAR\u00cdA \u00a0 \u00a0DEL \u00a0 ROSARIO \u00a0 GONZ\u00c1LEZ \u00a0 DE \u00a0LEMOS \u00a0\u00a0<\/p>\n<p>Aprobado Acta No. 287. \u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D.C., \u00a0septiembre \u00a0 catorce \u00a0 (14) \u00a0 de \u00a0 dos \u00a0 mil \u00a0 nueve \u00a0(2009) \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>La \u00a0Sala \u00a0emprende \u00a0el \u00a0estudio \u00a0sobre \u00a0las \u00a0exigencias \u00a0de l\u00f3gica y suficiente acreditaci\u00f3n del libelo casacional allegado \u00a0por \u00a0el \u00a0defensor \u00a0del \u00a0acusado \u00a0SIM\u00d3N LEMUS BARRETO \u00a0contra \u00a0el \u00a0fallo \u00a0de \u00a0segundo \u00a0grado \u00a0dictado \u00a0por el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1 \u00a0el \u00a013 \u00a0de \u00a0marzo \u00a0de \u00a02009, a trav\u00e9s del cual \u00a0confirm\u00f3 \u00a0la \u00a0sentencia \u00a0proferida \u00a0el \u00a010 \u00a0de diciembre de 2008 por el Juzgado \u00a0D\u00e9cimo \u00a0Penal \u00a0del \u00a0Circuito de Conocimiento de la misma ciudad, por cuyo medio \u00a0lo \u00a0conden\u00f3 \u00a0como \u00a0autor \u00a0penalmente \u00a0responsable \u00a0del \u00a0delito \u00a0de \u00a0tr\u00e1fico de \u00a0estupefacientes. \u00a0\u00a0<\/p>\n<p>HECHOS \u00a0<\/p>\n<p>Aproximadamente a las seis de la tarde del 15 \u00a0de \u00a0enero \u00a0de \u00a02008, \u00a0agentes \u00a0de la Polic\u00eda Nacional adelantaron una requisa a \u00a0SIM\u00d3N \u00a0LEMUS \u00a0en \u00a0la \u00a0v\u00eda \u00a0p\u00fablica \u00a0a \u00a0la altura de la calle 8\u00aa con carrera 16 de Bogot\u00e1, hallando en el \u00a0bolsillo \u00a0derecho \u00a0de \u00a0su \u00a0camiseta una sustancia que result\u00f3 ser marihuana, la \u00a0cual pes\u00f3 137.3 gramos, disponi\u00e9ndose su captura en flagrancia. \u00a0\u00a0<\/p>\n<p>ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0audiencia \u00a0celebrada ante el Juzgado Veintis\u00e9is Penal Municipal \u00a0de \u00a0Control de Garant\u00edas de Bogot\u00e1 el funcionario declar\u00f3 la captura ajustada \u00a0a \u00a0la Constituci\u00f3n. En la misma oportunidad la Fiscal\u00eda le imput\u00f3 al referido \u00a0ciudadano, \u00a0quien se encontraba asistido por su defensor,\u00a0 la comisi\u00f3n del \u00a0delito \u00a0de \u00a0tr\u00e1fico de estupefacientes al cual se allan\u00f3; en el curso de dicha \u00a0actuaci\u00f3n le fue otorgada libertad inmediata e incondicional. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a0 4 \u00a0de \u00a0febrero \u00a0de \u00a02008 \u00a0la \u00a0Fiscal\u00eda \u00a0present\u00f3 \u00a0escrito \u00a0de \u00a0acusaci\u00f3n \u00a0 contra \u00a0 el \u00a0 incriminado \u00a0 como \u00a0presunto \u00a0autor \u00a0del \u00a0punible \u00a0ya \u00a0mencionado. \u00a0\u00a0<\/p>\n<p>El \u00a0Juzgado \u00a0D\u00e9cimo \u00a0Penal del Circuito con \u00a0funciones \u00a0de \u00a0conocimiento \u00a0de \u00a0Bogot\u00e1 \u00a0profiri\u00f3 \u00a0fallo el 10 de diciembre de \u00a02008, \u00a0 por \u00a0 medio \u00a0 del \u00a0 cual \u00a0conden\u00f3 \u00a0a \u00a0SIM\u00d3N \u00a0LEMUS a la pena principal de treinta y tres (33) meses \u00a0y \u00a0ocho \u00a0(8) \u00a0d\u00edas \u00a0de \u00a0prisi\u00f3n \u00a0y \u00a0multa \u00a0por \u00a01.38 salarios m\u00ednimos legales \u00a0mensuales, \u00a0 como \u00a0 autor \u00a0 penalmente \u00a0 responsable \u00a0 del \u00a0 delito \u00a0al \u00a0que \u00a0se \u00a0allan\u00f3. \u00a0\u00a0<\/p>\n<p>En el mismo prove\u00eddo le neg\u00f3 la condena de \u00a0ejecuci\u00f3n \u00a0condicional, \u00a0as\u00ed \u00a0como \u00a0la prisi\u00f3n domiciliaria sustitutiva de la \u00a0intramural \u00a0 y \u00a0 la \u00a0 domiciliaria \u00a0 dispuesta \u00a0 para \u00a0 los \u00a0 padres \u00a0cabeza \u00a0de \u00a0familia. \u00a0\u00a0<\/p>\n<p>Mediante \u00a0fallo \u00a0del \u00a013 de marzo de 2009 el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Bogot\u00e1 confirm\u00f3 la sentencia de condena al conocer del \u00a0recurso \u00a0de apelaci\u00f3n interpuesto por la defensa, providencia contra la cual el \u00a0mismo \u00a0sujeto \u00a0procesal \u00a0interpuso \u00a0en \u00a0oportunidad \u00a0recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n y alleg\u00f3 el respectivo libelo. \u00a0\u00a0<\/p>\n<p>LA DEMANDA \u00a0<\/p>\n<p>Con \u00a0fundamento \u00a0en \u00a0la \u00a0causal \u00a0primera \u00a0de \u00a0casaci\u00f3n \u00a0establecida \u00a0en el art\u00edculo 181 de la Ley 906 de 2004, el recurrente \u00a0afirma \u00a0que \u00a0los sentenciadores interpretaron err\u00f3neamente varias disposiciones \u00a0(art\u00edculos \u00a06\u00ba \u00a0y 13 del C\u00f3digo Penal, 3\u00ba, 6\u00ba y 26 de la Ley 906 de 2004, y \u00a044 \u00a0 de \u00a0 la \u00a0Constituci\u00f3n \u00a0Pol\u00edtica), \u00a0as\u00ed \u00a0como \u00a0preceptos \u00a0del \u00a0bloque \u00a0de \u00a0constitucionalidad \u00a0(Pacto \u00a0de San Jos\u00e9 de Costa Rica) y jurisprudencias de las \u00a0altas \u00a0cortes \u00a0(\u201csentencias de Tutela N\u00fameros C-142 \u00a0del \u00a0a\u00f1o \u00a01996, \u00a0C.622 \u00a0del \u00a0a\u00f1o \u00a02003, \u00a0433 \u00a0del \u00a0a\u00f1o \u00a01997, \u00a0C-607 del a\u00f1o \u00a02003\u201d), \u00a0pues \u00a0no \u00a0se \u00a0ha \u00a0tenido \u00a0en \u00a0cuenta que el \u00a0derecho \u00a0de los menores prevalecen sobre los derechos de los dem\u00e1s, de modo que \u00a0el \u00a0acusado \u00a0en \u00a0su \u00a0condici\u00f3n de padre cabeza de familia debe permanecer en el \u00a0lugar \u00a0 de \u00a0 su \u00a0 domicilio \u00a0con \u00a0sus \u00a0dos \u00a0hijos \u00a0de \u00a04 \u00a0meses \u00a0y \u00a07 \u00a0a\u00f1os \u00a0de \u00a0edad. \u00a0\u00a0<\/p>\n<p>Apoyado \u00a0en \u00a0los \u00a0argumentos \u00a0anteriores, el \u00a0defensor \u00a0solicita \u00a0la \u00a0casaci\u00f3n \u00a0parcial del fallo impugnado, en el sentido de \u00a0otorgar \u00a0a \u00a0su \u00a0representado \u00a0la \u00a0prisi\u00f3n domiciliaria en raz\u00f3n de ostentar la \u00a0condici\u00f3n de padre cabeza de familia. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES DE LA SALA \u00a0<\/p>\n<p>Es \u00a0cierto \u00a0que \u00a0en la Ley 906 de 2004 no se \u00a0distingue \u00a0entre \u00a0recurso \u00a0de casaci\u00f3n por la v\u00eda com\u00fan y por la discrecional \u00a0en \u00a0cuanto \u00a0se \u00a0margin\u00f3 \u00a0la exigencia de la cantidad de pena m\u00e1xima del delito \u00a0para \u00a0acceder \u00a0a \u00a0dicha impugnaci\u00f3n, no obstante, es del resorte del recurrente \u00a0demostrar \u00a0el \u00a0quebranto \u00a0de \u00a0derechos o garant\u00edas fundamentales, lo cual exige \u00a0contar \u00a0con \u00a0inter\u00e9s \u00a0para impugnar, se\u00f1alar la causal, desarrollar los cargos \u00a0de \u00a0sustentaci\u00f3n \u00a0del \u00a0recurso \u00a0y demostrar la necesidad del fallo de casaci\u00f3n \u00a0para \u00a0cumplir alguno de los fines establecidos por el legislador en su art\u00edculo \u00a0180, \u00a0esto es, la efectividad del derecho material, el respeto de las garant\u00edas \u00a0de \u00a0los \u00a0intervinientes, la reparaci\u00f3n de los agravios sufridos por \u00e9stos y la \u00a0unificaci\u00f3n \u00a0de \u00a0la \u00a0jurisprudencia, so pena de resultar inadmitida la demanda, \u00a0seg\u00fan \u00a0 lo \u00a0 establece \u00a0 el \u00a0 art\u00edculo \u00a0 184 \u00a0 de \u00a0 la \u00a0 citada \u00a0 legislaci\u00f3n \u00a0adjetiva. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Ahora, \u00a0en \u00a0el \u00a0examen de los requisitos \u00a0de \u00a0admisibilidad \u00a0de \u00a0los \u00a0libelos \u00a0casacionales, \u00a0es \u00a0deber \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0Sala \u00a0 \u00a0 \u00a0constatar \u00a0en \u00a0la \u00a0 \u00a0formulaci\u00f3n \u00a0 \u00a0y \u00a0 desarrollo \u00a0 de \u00a0 \u00a0 \u00a0las \u00a0 \u00a0 censuras \u00a0 el \u00a0 acatamiento \u00a0de \u00a0las \u00a0exigencias \u00a0de \u00a0 l\u00f3gica \u00a0 \u00a0 \u00a0 \u00a0 y \u00a0 \u00a0 \u00a0 \u00a0 de\u00a0 \u00a0 \u00a0 pertinente \u00a0 \u00a0demostraci\u00f3n \u00a0 \u00a0 definidas \u00a0 \u00a0 por \u00a0 \u00a0 el \u00a0 \u00a0 legislador \u00a0 \u00a0y \u00a0desarrolladas \u00a0 por \u00a0 la \u00a0jurisprudencia, \u00a0con el fin \u00a0de \u00a0 \u00a0 \u00a0 \u00a0 evitar \u00a0 \u00a0 \u00a0 \u00a0la \u00a0 \u00a0 \u00a0 \u00a0transformaci\u00f3n \u00a0 \u00a0de \u00a0 \u00a0este \u00a0 recurso \u00a0extraordinario \u00a0 en \u00a0una \u00a0instancia \u00a0 \u00a0 adicional \u00a0 \u00a0 a \u00a0 \u00a0 las \u00a0 \u00a0 ordinarias. \u00a0 \u00a0 Tales \u00a0 \u00a0 requisitos \u00a0 se \u00a0orientan \u00a0a \u00a0conseguir \u00a0el \u00a0 desarrollo \u00a0 de \u00a0los \u00a0libelos \u00a0dentro \u00a0de \u00a0unos m\u00ednimos l\u00f3gicos y de coherencia en la postulaci\u00f3n y \u00a0demostraci\u00f3n \u00a0de \u00a0los \u00a0cargos \u00a0propuestos, \u00a0en cuanto \u00a0resulten \u00a0inteligibles, \u00a0esto \u00a0es, \u00a0precisos y claros, \u00a0pues \u00a0no \u00a0corresponde a la \u00a0Sala \u00a0en \u00a0su \u00a0funci\u00f3n \u00a0reglada \u00a0de \u00a0orden \u00a0constitucional \u00a0y \u00a0legal, \u00a0develar o \u00a0desentra\u00f1ar \u00a0el sentido de confusas, ambivalentes o contradictorias alegaciones \u00a0de los impugnantes en casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Efectuadas \u00a0 las \u00a0anteriores \u00a0precisiones, \u00a0advierte \u00a0la \u00a0Sala \u00a0en el reproche formulado por el defensor, que si bien invoca \u00a0la \u00a0 causal \u00a0primera \u00a0de \u00a0casaci\u00f3n \u00a0establecida \u00a0en \u00a0el \u00a0art\u00edculo \u00a0181 \u00a0de \u00a0la \u00a0legislaci\u00f3n \u00a0procesal \u00a0de \u00a02004, \u00a0esto \u00a0es, \u00a0la \u00a0violaci\u00f3n \u00a0directa \u00a0de la ley \u00a0sustancial, \u00a0no se atiene a desarrollar el cargo conforme a las reglas que rigen \u00a0tal postulaci\u00f3n. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, \u00a0la \u00a0denuncia \u00a0de \u00a0la violaci\u00f3n \u00a0directa \u00a0de \u00a0la ley sustancial tiene lugar cuando a partir de la apreciaci\u00f3n de \u00a0los \u00a0hechos \u00a0legal \u00a0y oportunamente acreditados dentro del diligenciamiento, los \u00a0falladores \u00a0omiten \u00a0aplicar \u00a0la \u00a0disposici\u00f3n \u00a0que \u00a0se ocupa de la situaci\u00f3n en \u00a0concreto, \u00a0en \u00a0cuanto \u00a0yerran \u00a0acerca \u00a0de \u00a0su existencia (falta de aplicaci\u00f3n o \u00a0exclusi\u00f3n \u00a0evidente), realizan una equ\u00edvoca adecuaci\u00f3n de los hechos probados \u00a0a \u00a0los \u00a0supuestos \u00a0que \u00a0contempla \u00a0el \u00a0precepto \u00a0(aplicaci\u00f3n \u00a0indebida), \u00a0o \u00a0le \u00a0atribuyen \u00a0a \u00a0la \u00a0norma \u00a0un sentido que no tiene o le asignan efectos diversos o \u00a0contrarios a su contenido (interpretaci\u00f3n err\u00f3nea). \u00a0\u00a0<\/p>\n<p>En \u00a0tal \u00a0caso, \u00a0sin \u00a0importar \u00a0la especie de \u00a0violaci\u00f3n \u00a0directa de la ley sustancial, el yerro de los juzgadores recae sobre \u00a0la \u00a0normatividad, \u00a0circunstancia que ubica el debate en un \u00e1mbito estrictamente \u00a0jur\u00eddico, \u00a0sea \u00a0porque \u00a0se dej\u00f3 de lado el precepto regulador de la situaci\u00f3n \u00a0espec\u00edfica \u00a0demostrada, \u00a0ora \u00a0porque \u00a0el \u00a0hecho \u00a0se \u00a0adecua \u00a0a una disposici\u00f3n \u00a0estructurada \u00a0con \u00a0supuestos \u00a0distintos \u00a0a \u00a0los \u00a0establecidos, o bien, porque se \u00a0desborda \u00a0el \u00a0entendimiento \u00a0propio de la norma aplicable al caso concreto, todo \u00a0lo \u00a0cual exige del casacionista la aceptaci\u00f3n de la realidad f\u00e1ctica declarada \u00a0en las instancias. \u00a0\u00a0<\/p>\n<p>En \u00a0consecuencia, \u00a0no \u00a0se \u00a0debate \u00a0all\u00ed \u00a0la \u00a0actividad \u00a0probatoria \u00a0ni su ulterior ponderaci\u00f3n por parte de los funcionarios \u00a0judiciales, \u00a0pues para emprender la censura de la validez de las pruebas o de su \u00a0apreciaci\u00f3n, \u00a0el \u00a0legislador ha establecido como causal la violaci\u00f3n indirecta \u00a0de \u00a0la ley sustancial, en cuanto su infracci\u00f3n se produce de manera mediata, de \u00a0conformidad \u00a0con \u00a0las diversas modalidades de errores en que pueden incurrir los \u00a0sentenciadores en tal materia. \u00a0\u00a0<\/p>\n<p>En \u00a0el \u00a0reproche que convoca el examen de la \u00a0Sala \u00a0se \u00a0advierte que si bien el demandante plantea la violaci\u00f3n directa de la \u00a0ley \u00a0sustancial, \u00a0su \u00a0reclamo \u00a0no \u00a0se adentra a ubicar el problema de naturaleza \u00a0jur\u00eddico \u00a0\u2013 \u00a0conceptual, \u00a0dado \u00a0que \u00a0orienta \u00a0su \u00a0esfuerzo \u00a0a \u00a0que se le otorgue a su asistido la prisi\u00f3n \u00a0domiciliaria \u00a0por \u00a0ser cabeza de familia, pero no atina a se\u00f1alar por qu\u00e9 ello \u00a0debe \u00a0ser \u00a0as\u00ed, es decir, no identifica con exactitud cu\u00e1l fue el yerro de los \u00a0falladores, \u00a0am\u00e9n \u00a0de \u00a0que \u00a0no \u00a0se \u00a0ocupa \u00a0de controvertir de alguna manera los \u00a0fundamentos \u00a0expuestos en las decisiones de primera y segunda instancia sobre el \u00a0particular. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0No \u00a0hay \u00a0duda \u00a0que \u00a0en virtud del art\u00edculo 44 de la Carta Pol\u00edtica \u00a0los \u00a0derechos \u00a0fundamentales \u00a0de los ni\u00f1os tienen especial val\u00eda y prevalencia \u00a0sobre \u00a0los de los dem\u00e1s, circunstancia que por s\u00ed sola no basta para pretextar \u00a0el \u00a0cumplimiento \u00a0de \u00a0las sanciones penales, pues de ser ello as\u00ed bastar\u00eda con \u00a0que \u00a0los \u00a0sentenciados \u00a0tuvieran \u00a0un \u00a0hijo menor para exonerarse del tratamiento \u00a0penitenciario \u00a0dispuesto \u00a0por \u00a0el Estado, argumento ad \u00a0absurdum, \u00a0que \u00a0denota \u00a0falta \u00a0de \u00a0sustentaci\u00f3n en el \u00a0reparo analizado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Adicionalmente \u00a0se \u00a0tiene \u00a0que \u00a0tampoco \u00a0el \u00a0demandante \u00a0se ocupa de \u00a0cuestionar \u00a0las \u00a0conclusiones \u00a0planteadas \u00a0por \u00a0esta Sala en casos como el de la \u00a0especie, \u00a0omisi\u00f3n \u00a0que deja sin demostraci\u00f3n alguna la censura y s\u00f3lo permite \u00a0advertir \u00a0que \u00a0en \u00a0forma \u00a0infructuosa \u00a0el \u00a0defensor pretende imponer su personal \u00a0aprehensi\u00f3n \u00a0del asunto por encima de lo decidido en el fallo, proceder ajeno a \u00a0este \u00a0recurso \u00a0extraordinario, pues de actuarse en tal forma se desconocer\u00eda la \u00a0presunci\u00f3n \u00a0de \u00a0acierto \u00a0y \u00a0legalidad \u00a0de \u00a0la \u00a0cual \u00a0se \u00a0encuentra revestida el \u00a0prove\u00eddo impugnado. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Tambi\u00e9n \u00a0se \u00a0consigue \u00a0constatar \u00a0que el censor no explica de qu\u00e9 \u00a0manera \u00a0se \u00a0violaron \u00a0los \u00a0preceptos \u00a0que \u00a0simplemente relaciona, adem\u00e1s de que \u00a0tampoco \u00a0 \u00a0dice \u00a0 \u00a0cu\u00e1l \u00a0 \u00a0es \u00a0 \u00a0el \u00a0 \u00a0contenido \u00a0 \u00a0de \u00a0 \u00a0las \u00a0 sentencias \u00a0 de \u00a0constitucionalidad \u00a0 que \u00a0simplemente \u00a0 \u00a0cita \u00a0 \u00a0y \u00a0 cu\u00e1l \u00a0 es \u00a0 su injerencia en el caso analizado. \u00a0\u00a0<\/p>\n<p>Las \u00a0mencionadas \u00a0omisiones \u00a0l\u00f3gicas y demostrativas en el discurso del \u00a0defensor imposibilitan a la \u00a0Sala \u00a0para \u00a0acometer \u00a0el \u00a0estudio \u00a0de la censura planteada, pues si el libelo de \u00a0casaci\u00f3n \u00a0no \u00a0corresponde \u00a0a \u00a0un alegato de libre confecci\u00f3n, su presentaci\u00f3n \u00a0con \u00a0base \u00a0en \u00a0meras \u00a0apreciaciones \u00a0personales \u00a0e indemostradas del \u00a0recurrente y \u00a0sin \u00a0atenerse a alguna de las reglas l\u00f3gicas y argumentativas que lo gobiernan, \u00a0impone \u00a0 la \u00a0inadmisi\u00f3n \u00a0de \u00a0la \u00a0demanda \u00a0de \u00a0acuerdo con lo dispuesto en el art\u00edculo 184 de la Ley 906 de \u00a02004, \u00a0 pues \u00a0 \u00a0en \u00a0 virtud \u00a0 del \u00a0 principio \u00a0 de \u00a0 limitaci\u00f3n \u00a0 propio \u00a0 \u00a0 \u00a0 \u00a0 del \u00a0 \u00a0 \u00a0 \u00a0tr\u00e1mite \u00a0casacional, la Corte no se \u00a0encuentra facultada para enmendar tales falencias. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Adem\u00e1s, \u00a0no se observa con ocasi\u00f3n de la \u00a0sentencia \u00a0impugnada o dentro del curso de la actuaci\u00f3n procesal, violaci\u00f3n de \u00a0derechos \u00a0 \u00a0o \u00a0 \u00a0garant\u00edas \u00a0 \u00a0del \u00a0 \u00a0incriminado, \u00a0 \u00a0como \u00a0 para \u00a0 adoptar \u00a0la \u00a0decisi\u00f3n \u00a0de \u00a0superar \u00a0los \u00a0defectos \u00a0de \u00a0la \u00a0demanda y \u00a0decidir \u00a0de \u00a0fondo, \u00a0seg\u00fan \u00a0lo \u00a0dispone \u00a0el \u00a0inciso 3\u00ba del art\u00edculo 184 de la \u00a0citada legislaci\u00f3n. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Precisi\u00f3n final \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Contra \u00a0la \u00a0decisi\u00f3n \u00a0de \u00a0inadmitir \u00a0la \u00a0demanda \u00a0presentada por la \u00a0defensa \u00a0procede \u00a0el \u00a0mecanismo de insistencia de conformidad con lo establecido \u00a0en \u00a0el art\u00edculo 186 de la Ley 906 de 2004. Como dicha legislaci\u00f3n no regula el \u00a0tr\u00e1mite \u00a0a \u00a0seguir \u00a0para \u00a0aplicar \u00a0el \u00a0referido \u00a0instituto procesal, la Sala ha \u00a0definido \u00a0 \u00a0las \u00a0 reglas \u00a0 para \u00a0 tal \u00a0 prop\u00f3sito1, como sigue: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0i) \u00a0 \u00a0 \u00a0 \u00a0La \u00a0insistencia \u00a0es un mecanismo especial cuyo ejercicio corresponde \u00a0al \u00a0demandante, \u00a0dentro \u00a0de los cinco (5) d\u00edas siguientes a la notificaci\u00f3n de \u00a0la \u00a0providencia \u00a0por \u00a0medio \u00a0de \u00a0la \u00a0cual la Sala decida inadmitir la demanda de \u00a0casaci\u00f3n, \u00a0con \u00a0el \u00a0fin \u00a0de provocar la reconsideraci\u00f3n de lo decido. Tambi\u00e9n \u00a0podr\u00e1 \u00a0ser ejercitado oficiosamente dentro del mismo t\u00e9rmino por alguno de los \u00a0Delegados \u00a0 del \u00a0 Ministerio \u00a0P\u00fablico \u00a0para \u00a0la \u00a0Casaci\u00f3n \u00a0Penal \u00a0\u2013 \u00a0cuando \u00a0el \u00a0recurso \u00a0de casaci\u00f3n no \u00a0hubiera \u00a0 \u00a0sido \u00a0 \u00a0interpuesto \u00a0 por \u00a0 un \u00a0 Procurador \u00a0 Judicial \u00a0 \u2013, \u00a0el Magistrado disidente, el ausente \u00a0de los debates o quien no haya suscrito la providencia inadmisoria. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0ii) \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0La \u00a0solicitud de insistencia puede elevarse ante \u00a0el \u00a0Ministerio \u00a0P\u00fablico \u00a0a \u00a0trav\u00e9s \u00a0de sus Delegados para la Casaci\u00f3n Penal o \u00a0ante \u00a0uno \u00a0de \u00a0los \u00a0Magistrados \u00a0de \u00a0la \u00a0Sala \u00a0en \u00a0las \u00a0condiciones expuestas en \u00a0precedencia. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0iii) \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0Es \u00a0potestativo \u00a0del \u00a0Magistrado \u00a0disidente, \u00a0de \u00a0quien \u00a0no \u00a0intervino \u00a0en los debates o del Delegado del Ministerio P\u00fablico ante \u00a0el \u00a0cual se formula la insistencia, optar por someter el asunto a consideraci\u00f3n \u00a0de \u00a0la \u00a0Sala \u00a0o \u00a0no \u00a0presentarlo \u00a0para \u00a0su \u00a0revisi\u00f3n. \u00a0En \u00a0\u00e9ste \u00faltimo evento \u00a0informar\u00e1 \u00a0 de \u00a0 ello \u00a0 al \u00a0 peticionario \u00a0 en \u00a0 un \u00a0 plazo \u00a0 de \u00a0 quince \u00a0(15) \u00a0d\u00edas. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0iv) \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0El \u00a0auto \u00a0a \u00a0trav\u00e9s \u00a0del \u00a0cual \u00a0se \u00a0inadmite la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0trae \u00a0como \u00a0consecuencia \u00a0la \u00a0firmeza de la sentencia de \u00a0segunda \u00a0instancia \u00a0contra \u00a0la \u00a0cual \u00a0se formul\u00f3 el recurso de casaci\u00f3n, salvo \u00a0cuando la insistencia prospere y conlleve la admisi\u00f3n del libelo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, la CORTE SUPREMA DE JUSTICIA, SALA DE \u00a0CASACI\u00d3N PENAL, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0INADMITIR \u00a0el \u00a0libelo \u00a0casacional \u00a0presentado \u00a0por \u00a0el \u00a0defensor \u00a0del \u00a0procesado \u00a0 \u00a0SIM\u00d3N \u00a0 \u00a0LEMUS \u00a0 \u00a0BARRETO, \u00a0 \u00a0por \u00a0 \u00a0las \u00a0 \u00a0razones \u00a0 \u00a0expuestas \u00a0 en \u00a0 las \u00a0 consideraciones \u00a0precedentes. \u00a0\u00a0<\/p>\n<p>De \u00a0 \u00a0 conformidad \u00a0 \u00a0con \u00a0el \u00a0art\u00edculo \u00a0184 \u00a0de la Ley 906 de \u00a02004, es facultad del demandante elevar petici\u00f3n de insistencia. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>JULIO \u00a0ENRIQUE \u00a0SOCHA SALAMANCA \u00a0\u00a0<\/p>\n<p>JOS\u00c9 LEONIDAS BUSTOS MART\u00cdNEZ \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0SIGIFREDO \u00a0 \u00a0ESPINOSA \u00a0P\u00c9REZ \u00a0\u00a0<\/p>\n<p>ALFREDO \u00a0 G\u00d3MEZ \u00a0 QUINTERO \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0MAR\u00cdA DEL ROSARIO GONZ\u00c1LEZ DE \u00a0LEMOS \u00a0\u00a0<\/p>\n<p>AUGUSTO \u00a0J. \u00a0IB\u00c1\u00d1EZ \u00a0GUZM\u00c1N \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0JORGE \u00a0 \u00a0LUIS \u00a0 QUINTERO \u00a0MILANES \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>YESID \u00a0 RAM\u00cdREZ \u00a0 BASTIDAS \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0JAVIER ZAPATA ORT\u00cdZ \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p>1 \u00a0Providencia del 12 de diciembre de 2005. Rad. 24322. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso \u00a0 \u00a0 No \u00a032082 \u00a0\u00a0 CORTE \u00a0 SUPREMA \u00a0 DE \u00a0JUSTICIA \u00a0\u00a0 SALA \u00a0 DE \u00a0 CASACI\u00d3N \u00a0PENAL \u00a0\u00a0 Magistrada Ponente: \u00a0 MAR\u00cdA \u00a0 \u00a0DEL \u00a0 ROSARIO \u00a0 GONZ\u00c1LEZ \u00a0 DE \u00a0LEMOS \u00a0\u00a0 Aprobado Acta No. 287. \u00a0 Bogot\u00e1 \u00a0D.C., \u00a0septiembre \u00a0 catorce \u00a0 (14) \u00a0 de \u00a0 dos \u00a0 mil \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-19376","post","type-post","status-publish","format-standard","hentry","category-17"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/19376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=19376"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/19376\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=19376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=19376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=19376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}