{"id":18907,"date":"2023-09-11T19:44:54","date_gmt":"2023-09-11T19:44:54","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3155128-10-09\/"},"modified":"2023-09-11T19:44:54","modified_gmt":"2023-09-11T19:44:54","slug":"3155128-10-09","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/11\/3155128-10-09\/","title":{"rendered":"31551(28-10-09)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 31551 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>JAVIER ZAPATA ORTIZ \u00a0<\/p>\n<p>Aprobado Acta No. \u00a0339 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Bogot\u00e1 \u00a0 D. \u00a0 C., \u00a0veintiocho \u00a0(28) \u00a0de \u00a0octubre de dos mil nueve (2009) \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>VISTOS: \u00a0\u00a0<\/p>\n<p>Surtido \u00a0el \u00a0traslado \u00a0que \u00a0establece \u00a0el \u00a0art\u00edculo \u00a0500 \u00a0del \u00a0C\u00f3digo de Procedimiento Penal, Ley 906 de 2004, la Sala de \u00a0Casaci\u00f3n \u00a0Penal \u00a0emite \u00a0concepto sobre la extradici\u00f3n del ciudadano colombiano \u00a0JOS\u00c9 \u00a0DE \u00a0JES\u00daS \u00a0LE\u00d3N \u00a0NI\u00d1O, \u00a0solicitada \u00a0por \u00a0el \u00a0Gobierno \u00a0 de \u00a0 los \u00a0 Estados \u00a0 Unidos \u00a0de \u00a0Am\u00e9rica \u00a0a trav\u00e9s de su Embajada en \u00a0Colombia, \u00a0 para \u00a0 que \u00a0 comparezca \u00a0 a \u00a0juicio \u00a0 \u00a0por \u00a0 \u00a0delitos \u00a0 federales \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0narc\u00f3ticos.\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>ANTECEDENTES: \u00a0\u00a0<\/p>\n<p>1. Con Nota Verbal \u00a0No. \u00a0 \u00a03417 \u00a0 \u00a0 \u00a0 \u00a0 del \u00a0 \u00a0 \u00a0 \u00a0 22 \u00a0 \u00a0de \u00a0diciembre \u00a0 de \u00a02008, \u00a0la \u00a0Embajada \u00a0 de \u00a0 los \u00a0 Estados \u00a0 Unidos \u00a0de \u00a0Am\u00e9rica \u00a0en \u00a0nuestro pa\u00eds solicit\u00f3 \u00a0la \u00a0detenci\u00f3n \u00a0provisional \u00a0con \u00a0fines de extradici\u00f3n del ciudadano colombiano \u00a0JOS\u00c9 \u00a0DE \u00a0JES\u00daS \u00a0LE\u00d3N \u00a0NI\u00d1O, identificado con la \u00a0c\u00e9dula \u00a0de \u00a0ciudadan\u00eda \u00a0No. \u00a019.305.030, \u00a0requerido para comparecer a \u00a0 \u00a0 juicio \u00a0 \u00a0 por \u00a0 \u00a0 delitos \u00a0 \u00a0 \u00a0 \u00a0federales \u00a0 \u00a0 \u00a0 \u00a0de \u00a0narc\u00f3ticos, de conformidad con los cargos atribuidos \u00a0en \u00a0la \u00a0Acusaci\u00f3n \u00a0No. 08-CRIM 1003 del 16 de octubre \u00a0de \u00a02008, \u00a0dictada \u00a0en la Corte Distrital de los Estados Unidos para el Distrito \u00a0Sur de Nueva York. \u00a0\u00a0<\/p>\n<p>2. \u00a0Recibida \u00a0la \u00a0Nota \u00a0 Verbal, \u00a0 el \u00a0 Ministerio \u00a0 de \u00a0 Relaciones \u00a0 Exteriores \u00a0remiti\u00f3 \u00a0copia \u00a0al \u00a0 Fiscal \u00a0 General \u00a0de \u00a0la \u00a0Naci\u00f3n, \u00a0quien \u00a0con \u00a0resoluci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del \u00a0 \u00a0 \u00a0 \u00a0 29 \u00a0 \u00a0 de \u00a0diciembre \u00a0 \u00a0 \u00a0de \u00a02008, \u00a0decret\u00f3 la captura \u00a0con \u00a0fines \u00a0de \u00a0extradici\u00f3n del requerido, la cual se \u00a0hizo \u00a0 \u00a0efectiva \u00a0 \u00a0el \u00a022 \u00a0 \u00a0 de \u00a0 enero \u00a0 de \u00a0 2009 \u00a0 por \u00a0miembros \u00a0de \u00a0la Polic\u00eda Judicial \u00a0de \u00a0la \u00a0Fiscal\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n.\u00a0 \u00a0\u00a0<\/p>\n<p>3. \u00a0La Embajada \u00a0de \u00a0los \u00a0Estados \u00a0Unidos de Am\u00e9rica, con Nota Verbal \u00a0No. \u00a0 0621 \u00a0 del \u00a019 \u00a0de \u00a0marzo \u00a0de \u00a0 2009, \u00a0formaliz\u00f3 \u00a0la \u00a0solicitud \u00a0de extradici\u00f3n, en la que \u00a0se \u00a0resumen los \u00a0 \u00a0hechos \u00a0 y \u00a0 los \u00a0 fundamentos \u00a0probatorios \u00a0 \u00a0de \u00a0 las \u00a0 imputaciones \u00a0 delictivas \u00a0contenidas \u00a0en \u00a0la \u00a0Acusaci\u00f3n \u00a0No. \u00a008-CRIM \u00a01003, \u00a0dictada \u00a0el \u00a016 \u00a0 de \u00a0octubre \u00a0de \u00a02008 \u00a0en la \u00a0Corte \u00a0Distrital \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0para el Distrito Sur de Nueva \u00a0 York, \u00a0 donde \u00a0 se\u00f1ala \u00a0 que \u00a0el \u00a0 requerido \u00a0es \u00a0miembro \u00a0de \u00a0una \u00a0organizaci\u00f3n \u00a0internacional \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dedicada al \u00a0tr\u00e1fico \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 narc\u00f3ticos \u00a0 \u00a0 que \u00a0importaba \u00a0hero\u00edna a los Estados \u00a0Unidos \u00a0 \u00a0 y \u00a0 \u00a0 luego \u00a0 \u00a0 la \u00a0 \u00a0 distribu\u00eda, \u00a0 \u00a0 utilizando \u00a0 \u00a0\u201ccorreos\u201d \u00a0humanos \u00a0para \u00a0transportar \u00a0los \u00a0 estupefacientes \u00a0 y \u00a0 devolver \u00a0 a \u00a0 Colombia \u00a0\u2013generalmente a trav\u00e9s \u00a0de \u00a0terceros \u00a0pa\u00edses \u00a0tales \u00a0como Rep\u00fablica Dominicana- el dinero producto del \u00a0tr\u00e1fico \u00a0il\u00edcito \u00a0(Folio \u00a096\u00a0 \u00a0a 103 \u00a0 y \u00a0 198 \u00a0 a \u00a0 202 \u00a0carpeta\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0anexa). \u00a0\u00a0<\/p>\n<p>En \u00a0 la \u00a0 mencionada \u00a0 acusaci\u00f3n \u00a0 se \u00a0formulan \u00a0los \u00a0siguientes \u00a0cargos: \u00a0\u00a0<\/p>\n<p>\u201c&#8211; \u00a0Cargo \u00a0Uno: \u00a0 \u00a0 Concierto \u00a0(i) \u00a0para \u00a0importar \u00a0a \u00a0los Estados Unidos, desde \u00a0un \u00a0lugar fuera de los Estados Unidos, un kilogramo o \u00a0m\u00e1s \u00a0 de \u00a0hero\u00edna, \u00a0en \u00a0violaci\u00f3n \u00a0del \u00a0T\u00edtulo \u00a021, \u00a0Secciones \u00a0812, \u00a0952 \u00a0(a), \u00a0 960 \u00a0 (a) \u00a0 (1), \u00a0 960 \u00a0 (b) \u00a0 (1) \u00a0 (A), \u00a0y \u00a0963\u00a0 \u00a0del C\u00f3digo de \u00a0los \u00a0 \u00a0Estados \u00a0 \u00a0Unidos; \u00a0 y \u00a0 (ii) \u00a0 para \u00a0distribuir \u00a0un \u00a0kilogramo \u00a0o \u00a0m\u00e1s \u00a0de \u00a0hero\u00edna, \u00a0sabiendo \u00a0que \u00a0dicha hero\u00edna iba a \u00a0ser \u00a0importada \u00a0a \u00a0los \u00a0Estados Unidos, en violaci\u00f3n \u00a0del \u00a0T\u00edtulo 21, Secciones \u00a0812, \u00a0 \u00a0959 \u00a0(a), \u00a0960 (b) (1) (A),\u00a0 \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 \u00a0963 \u00a0 \u00a0 \u00a0 del \u00a0 \u00a0 \u00a0C\u00f3digo \u00a0de \u00a0los Estados Unidos; y \u00a0\u00a0<\/p>\n<p>&#8211;Cargo \u00a0 \u00a0Dos: \u00a0 \u00a0Concierto \u00a0 \u00a0para \u00a0distribuir, \u00a0y \u00a0para \u00a0poseer \u00a0con \u00a0la \u00a0intenci\u00f3n de \u00a0distribuir, \u00a0un \u00a0kilogramo \u00a0o \u00a0m\u00e1s \u00a0de \u00a0hero\u00edna, \u00a0en \u00a0violaci\u00f3n \u00a0del \u00a0T\u00edtulo 21, Secciones 812, 841 (a) \u00a0(1), \u00a0841 \u00a0(b) \u00a0(1) \u00a0(A) \u00a0(i), \u00a0y \u00a0846 del \u00a0C\u00f3digo \u00a0de \u00a0los \u00a0Estados \u00a0Unidos. \u00a0\u00a0<\/p>\n<p>La \u00a0acusaci\u00f3n tambi\u00e9n incluye la pena de \u00a0decomiso \u00a0de conformidad con el T\u00edtulo 21, Secciones \u00a0853 \u00a0y \u00a0970 del \u00a0C\u00f3digo \u00a0de \u00a0los Estados Unidos, la cual busca el decomiso de \u00a0todos \u00a0los \u00a0bienes que se hayan derivado de ingresos obtenidos como resultado de \u00a0la \u00a0comisi\u00f3n \u00a0de \u00a0los \u00a0anteriores \u00a0delitos. \u00a0Si \u00a0dichos \u00a0bienes \u00a0no \u00a0estuvieren \u00a0disponibles, \u00a0 \u00a0 las \u00a0normas \u00a0anteriores \u00a0permiten que otros bienes \u00a0del acusado sean decomisados.\u201d \u00a0\u00a0<\/p>\n<p>Se \u00a0 explica \u00a0c\u00f3mo \u00a0en \u00a0el \u00a0curso del \u00a0concierto, \u00a0JOS\u00c9 \u00a0DE JES\u00daS LE\u00d3N NI\u00d1O, \u00a0era \u00a0uno \u00a0de \u00a0los \u00a0l\u00edderes \u00a0de la \u00a0organizaci\u00f3n \u00a0y los due\u00f1os de la hero\u00edna importada \u00a0a \u00a0 \u00a0 los \u00a0 \u00a0 Estados \u00a0 \u00a0 Unidos \u00a0 \u00a0 y, \u00a0suministraba \u00a0los \u00a0narc\u00f3ticos \u00a0a \u00a0terceras personas \u00a0para \u00a0su \u00a0transporte \u00a0a \u00a0trav\u00e9s \u00a0de \u00a0pa\u00edses centroamericanos hasta los Estados \u00a0Unidos; \u00a0 \u00a0 dicha \u00a0actividad \u00a0desarrollada \u00a0desde \u00a0 el \u00a0 11 \u00a0 de \u00a0marzo \u00a0de \u00a02001 \u00a0hasta \u00a0 \u00a0el \u00a0 26 \u00a0 de \u00a0 octubre \u00a0 \u00a0de \u00a0 2008, \u00a0 se demuestra con la interceptaci\u00f3n de \u00a0comunicaciones \u00a0telef\u00f3nicas judicialmente autorizadas en Colombia y los Estados \u00a0Unidos, \u00a0 \u00a0 las \u00a0 \u00a0vigilancias, \u00a0 \u00a0las \u00a0 \u00a0 \u00a0 \u00a0 incautaciones \u00a0a \u00a0la \u00a0organizaci\u00f3n \u00a0de 6 y 1.5 \u00a0kilogramos \u00a0 de \u00a0 hero\u00edna \u00a0 en \u00a0 Nueva \u00a0 York \u00a0 y \u00a0Nueva \u00a0Jersey, \u00a0y \u00a0la\u00a0 \u00a0manifestaci\u00f3n \u00a0de \u00a0los testigos que colaboran con el \u00a0gobierno \u00a0 \u00a0 \u00a0 \u00a0 de \u00a0 \u00a0 \u00a0 \u00a0 Norteam\u00e9rica. \u00a0\u00a0<\/p>\n<p>Afirma, \u00a0que \u00a0todas \u00a0las \u00a0acciones \u00a0fueron \u00a0ejecutadas \u00a0 \u00a0por \u00a0 \u00a0el \u00a0 \u00a0acusado \u00a0 \u00a0con posterioridad al 17 de diciembre de 1997. \u00a0\u00a0<\/p>\n<p>Con \u00a0 relaci\u00f3n \u00a0 a \u00a0 la \u00a0 identidad \u00a0de \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 \u00a0LE\u00d3N \u00a0 NI\u00d1O, \u00a0tambi\u00e9n \u00a0conocido \u00a0con el alias de \u00a0\u201cJos\u00e9 \u00a0Le\u00f3n\u201d, \u00a0 \u00a0 \u00a0dice \u00a0 \u00a0 que \u00a0 \u00a0 es \u00a0ciudadano \u00a0colombiano, \u00a0nacido \u00a0el \u00a029 \u00a0de \u00a0abril \u00a0de \u00a0 1956 \u00a0 \u00a0 \u00a0 \u00a0 en \u00a0 \u00a0 \u00a0 \u00a0Colombia, \u00a0y \u00a0es portador de la c\u00e9dula \u00a0de \u00a0 \u00a0ciudadan\u00eda \u00a0 \u00a0No. \u00a0 \u00a019.305.030. \u00a0\u00a0<\/p>\n<p>Con \u00a0la nota diplom\u00e1tica fueron remitidos \u00a0los \u00a0siguientes \u00a0documentos, \u00a0autenticados \u00a0y \u00a0traducidos \u00a0al \u00a0castellano, \u00a0para \u00a0sustentar la solicitud de extradici\u00f3n: \u00a0\u00a0<\/p>\n<p>3.1. \u00a0 Declaraci\u00f3n \u00a0jurada \u00a0rendida \u00a0el \u00a09 \u00a0 de \u00a0 febrero \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 2009, \u00a0 \u00a0 \u00a0 \u00a0por \u00a0 \u00a0 \u00a0 Marshall \u00a0A. \u00a0Camp, \u00a0Fiscal \u00a0Auxiliar \u00a0de \u00a0los Estados Unidos en \u00a0el Distrito Meridional \u00a0de \u00a0Nueva \u00a0York. Se refiere \u00a0al \u00a0 \u00a0procedimiento \u00a0 \u00a0cumplido \u00a0 \u00a0por \u00a0 \u00a0el \u00a0 Gran \u00a0Jurado \u00a0para \u00a0dictar \u00a0la \u00a0acusaci\u00f3n; \u00a0presenta \u00a0una \u00a0s\u00edntesis \u00a0de \u00a0los \u00a0hechos \u00a0que \u00a0dieron \u00a0lugar \u00a0a \u00a0la solicitud de extradici\u00f3n, \u00a0concreta\u00a0 \u00a0 los \u00a0 cargos \u00a0 formulados \u00a0 contra \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 \u00a0LE\u00d3N \u00a0 NI\u00d1O; precisa los elementos integrantes de \u00a0cada \u00a0 delito \u00a0 y \u00a0 aporta \u00a0 los \u00a0datos \u00a0allegados \u00a0a \u00a0la \u00a0investigaci\u00f3n \u00a0sobre \u00a0la \u00a0 \u00a0 identidad \u00a0 \u00a0 del \u00a0 \u00a0requerido \u00a0 (Folio \u00a0118 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2013 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0127 \u00a0carpeta \u00a0 anexa). \u00a0\u00a0<\/p>\n<p>3.2. \u00a0 Acusaci\u00f3n \u00a0 No. \u00a0 08-CRIM \u00a0 \u00a0 \u00a0 1003, \u00a0 \u00a0 \u00a0dictada \u00a0 \u00a0 el \u00a0 \u00a016 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0 octubre \u00a0 \u00a0 \u00a0de \u00a02008, en \u00a0la \u00a0Corte \u00a0Distrital \u00a0de \u00a0los Estados Unidos para el \u00a0Distrito \u00a0Sur \u00a0de \u00a0Nueva \u00a0York \u00a0(Folios \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 96 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2013 \u00a0103 y \u00a0198 \u00a0a \u00a0202\u00a0 carpeta \u00a0anexa). \u00a0\u00a0<\/p>\n<p>3.3. \u00a0Declaraci\u00f3n \u00a0jurada \u00a0del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 9 \u00a0 \u00a0de \u00a0febrero \u00a0 \u00a0 \u00a0de \u00a02009, \u00a0 de \u00a0Kenneth \u00a0E. \u00a0Mckindra, \u00a0Agente \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Especial \u00a0de \u00a0la \u00a0Administraci\u00f3n para el\u00a0 Control \u00a0de \u00a0 \u00a0 \u00a0 Drogas \u00a0(DEA), \u00a0quien proporciona \u00a0informaci\u00f3n \u00a0adicional \u00a0sobre \u00a0la investigaci\u00f3n, la \u00a0actividad, \u00a0la \u00a0manera \u00a0de \u00a0operar \u00a0de \u00a0la \u00a0organizaci\u00f3n \u00a0criminal y \u00a0 \u00a0la \u00a0 \u00a0identidad \u00a0 \u00a0del \u00a0 acusado \u00a0(Folio \u00a071 \u00a0&#8211; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 88 \u00a0carpeta\u00a0 \u00a0anexa). \u00a0\u00a0<\/p>\n<p>3.4. \u00a0Transcripci\u00f3n \u00a0de las disposiciones \u00a0penales \u00a0 sustantivas \u00a0 supuestamente \u00a0 transgredidas \u00a0 por \u00a0 el \u00a0 requerido \u00a0en \u00a0extradici\u00f3n \u00a0 con \u00a0 las \u00a0 conductas \u00a0 que \u00a0 se \u00a0le \u00a0endilgan \u00a0 \u00a0 (Folio \u00a0105\u00a0 &#8211; 114 \u00a0carpeta \u00a0anexa). \u00a0\u00a0<\/p>\n<p>3.5. \u00a0Fotograf\u00edas \u00a0de algunos miembros de \u00a0la \u00a0 organizaci\u00f3n \u00a0delictiva, \u00a0entre \u00a0ellas \u00a0la \u00a0de \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 \u00a0LE\u00d3N \u00a0 NI\u00d1O \u00a0(Folio 67 \u00a0carpeta \u00a0 anexa). \u00a0\u00a0<\/p>\n<p>3.6. \u00a0Copia \u00a0de \u00a0la \u00a0orden de captura y el informe dando cuenta de las \u00a0circunstancias \u00a0en \u00a0que se realiz\u00f3 la aprehensi\u00f3n y \u00a0los \u00a0informes \u00a0rendidos \u00a0sobre \u00a0el particular (Folios \u00a015 \u00a0 \u00a0\u2013 \u00a018, 26 \u00a0\u2013 \u00a0 29 \u00a0y \u00a0 \u00a093 \u00a0carpeta anexa). \u00a0\u00a0<\/p>\n<p>4. El Ministerio del Interior y de Justicia \u00a0estim\u00f3 \u00a0que el expediente se encontraba completo y la solicitud de extradici\u00f3n \u00a0formalizada, \u00a0por \u00a0lo cual, lo envi\u00f3 a la Sala de Casaci\u00f3n Penal para lo de su \u00a0competencia. \u00a0Adjunt\u00f3 \u00a0el \u00a0concepto rendido por el Jefe de la Oficina Jur\u00eddica \u00a0del \u00a0Ministerio \u00a0Relaciones Exteriores, en el sentido \u00a0que \u00a0al \u00a0no existir \u00a0tratado \u00a0de extradici\u00f3n aplicable entre Estados Unidos y \u00a0Colombia, \u00a0 es \u00a0 procedente \u00a0 obrar \u00a0de \u00a0conformidad \u00a0con \u00a0lo \u00a0dispuesto \u00a0en \u00a0el \u00a0ordenamiento jur\u00eddico penal colombiano. \u00a0\u00a0<\/p>\n<p>5. \u00a0 \u00a0El \u00a0 \u00a0requerido \u00a0 \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 LE\u00d3N \u00a0 NI\u00d1O \u00a0otorg\u00f3 \u00a0poder \u00a0a \u00a0una \u00a0abogada \u00a0de \u00a0la \u00a0Defensor\u00eda \u00a0P\u00fablica \u00a0 \u00a0y \u00a0 \u00a0se \u00a0 observ\u00f3 \u00a0 el \u00a0 traslado \u00a0 para \u00a0 solicitar \u00a0 pruebas, \u00a0dentro \u00a0del \u00a0cual \u00a0ninguno de los intervinientes hizo \u00a0uso \u00a0de \u00a0este \u00a0derecho, y \u00a0la \u00a0Corte \u00a0no dispuso la \u00a0pr\u00e1ctica de oficio, porque no lo consider\u00f3 necesario. \u00a0\u00a0<\/p>\n<p>DE LOS ALEGATOS FINALES \u00a0<\/p>\n<p>Dentro del t\u00e9rmino legal establecido en el \u00a0art\u00edculo \u00a0500 \u00a0de \u00a0la \u00a0Ley \u00a0906 de 2004, presentaron \u00a0sus \u00a0 \u00a0 puntos \u00a0 \u00a0 de \u00a0 \u00a0 vista \u00a0 \u00a0 la \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 defensora \u00a0 \u00a0y \u00a0 \u00a0la \u00a0 \u00a0Procuradur\u00eda \u00a0 General \u00a0 de \u00a0 la \u00a0 Naci\u00f3n \u00a0 a \u00a0 trav\u00e9s \u00a0 de \u00a0su \u00a0Delegada \u00a0 para \u00a0 la \u00a0Casaci\u00f3n \u00a0 Penal.\u00a0 \u00a0\u00a0<\/p>\n<p>1. \u00a0 \u00a0La \u00a0Procuradora \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Tercera \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Delegada \u00a0para \u00a0la Casaci\u00f3n Penal sintetiza la actuaci\u00f3n cumplida, y se\u00f1ala que, seg\u00fan \u00a0el \u00a0concepto \u00a0del \u00a0Ministerio de Relaciones Exteriores y ante la inexistencia de \u00a0un \u00a0tratado \u00a0de \u00a0extradici\u00f3n \u00a0en \u00a0vigor, \u00a0es \u00a0aplicable \u00a0al \u00a0caso \u00a0el \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0concretamente la Ley 906 de 2004. \u00a0\u00a0<\/p>\n<p>Luego \u00a0de referirse a los antecedentes del \u00a0tr\u00e1mite \u00a0y \u00a0mencionar la documentaci\u00f3n exigida de acuerdo a lo previsto por el \u00a0art\u00edculo \u00a0495 \u00a0de la ley en cita, sugiere a la Sala rendir concepto favorable a \u00a0la \u00a0 entrega, \u00a0 por \u00a0 considerar \u00a0 reunidos \u00a0 los \u00a0 requisitos \u00a0 exigidos \u00a0 para \u00a0concederla. \u00a0\u00a0<\/p>\n<p>As\u00ed, \u00a0 sostiene \u00a0 que \u00a0la \u00a0documentaci\u00f3n \u00a0allegada por el Gobierno solicitante, se \u00a0 halla \u00a0 debidamente \u00a0aportada \u00a0en \u00a0cuanto \u00a0fue \u00a0expedida \u00a0y \u00a0autenticada por las autoridades correspondientes en el \u00a0pa\u00eds requirente, lo que permite concluir su validez formal. \u00a0\u00a0<\/p>\n<p>En \u00a0 cuanto \u00a0 a \u00a0los \u00a0dem\u00e1s \u00a0requisitos \u00a0se\u00f1alados \u00a0 por \u00a0 el \u00a0 art\u00edculo \u00a0 502 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0estima el Ministerio P\u00fablico que se hallan reunidos \u00a0en \u00a0este \u00a0tr\u00e1mite para emitir el concepto de rigor, que en su criterio debe ser \u00a0favorable, \u00a0 \u00a0 \u00a0 exhortando \u00a0 \u00a0 \u00a0 al \u00a0Gobierno \u00a0Nacional \u00a0para \u00a0que \u00a0se \u00a0advierta \u00a0al \u00a0pa\u00eds \u00a0reclamante \u00a0sobre \u00a0la \u00a0necesidad de garantizar los derechos \u00a0fundamentales \u00a0al requerido de conformidad con los art\u00edculos 11, 12, 29 y 34 de \u00a0la \u00a0 Constituci\u00f3n \u00a0 Pol\u00edtica; \u00a0 9 \u00a0 y \u00a010 \u00a0de \u00a0la \u00a0Declaraci\u00f3n \u00a0 \u00a0 Universal \u00a0 \u00a0 de \u00a0 \u00a0 Derechos \u00a0 \u00a0 Humanos; \u00a0 \u00a0 5-3.6, \u00a0 \u00a07-2.5, \u00a08-1.2(a)(b)(c)(d)(f)(g)(h).3.4.5, \u00a09 \u00a0de \u00a0la \u00a0Convenci\u00f3n \u00a0Americana de Derechos \u00a0Humanos; \u00a09-2.3, \u00a010-1.1.2.3, \u00a014-1.2.3.5, \u00a0y \u00a015 \u00a0del \u00a0Pacto \u00a0Internacional \u00a0de \u00a0Derechos \u00a0 Civiles \u00a0 y \u00a0 Pol\u00edticos \u00a0 (Folios \u00a0 \u00a0 29 \u00a0 \u00a0a \u00a0 \u00a038 cuaderno principal). \u00a0\u00a0<\/p>\n<p>2. La defensora \u00a0del \u00a0solicitado en extradici\u00f3n present\u00f3 escrito con el que manifiesta no tener \u00a0objeci\u00f3n alguna sobre el tr\u00e1mite y el cumplimiento \u00a0de \u00a0los \u00a0requisitos \u00a0para \u00a0la \u00a0entrega de su procurado, sin embargo, a manera de \u00a0\u201cuna \u00a0 \u00a0constancia \u00a0 \u00a0hist\u00f3rica\u201d, \u00a0afirma \u00a0que \u00a0al \u00a0se\u00f1or \u00a0Le\u00f3n Ni\u00f1o \u00a0lo \u00a0ha \u00a0podido \u00a0investigar \u00a0y \u00a0juzgar \u00a0la \u00a0justicia \u00a0colombiana \u00a0teniendo \u00a0en \u00a0cuenta \u00a0que \u00a0los delitos se originaron en este \u00a0pa\u00eds \u00a0y \u00a0que \u00a0con \u00a0la \u00a0extradici\u00f3n \u00a0no \u00a0se ha logrado disminuir el narcotr\u00e1fico, por \u00a0tanto, \u00a0el \u00a0concepto \u00a0deber\u00eda \u00a0ser desfavorable; pero en caso que sea positivo, \u00a0pide \u00a0a la Corte, se condicione la entrega al respeto \u00a0de \u00a0 \u00a0 las \u00a0 \u00a0garant\u00edas \u00a0 \u00a0fundamentales \u00a0 \u00a0reconocidos \u00a0 \u00a0por \u00a0 \u00a0el \u00a0 \u00a0derecho \u00a0internacional \u00a0 \u00a0 \u00a0humanitario \u00a0 \u00a0 \u00a0a \u00a0todo \u00a0ser \u00a0humano \u00a0en \u00a0la \u00a0condici\u00f3n \u00a0de procesado, \u00a0se \u00a0le \u00a0otorgue \u00a0un \u00a0trato \u00a0digno, \u00a0no \u00a0sea sometido a prisi\u00f3n \u00a0perpetua, ni tratos crueles, degradantes o inhumanos. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE \u00a0LA \u00a0SALA \u00a0\u00a0<\/p>\n<p>1.- Cuestiones Previas \u00a0<\/p>\n<p>De \u00a0 \u00a0acuerdo \u00a0 \u00a0con \u00a0 \u00a0el \u00a0art\u00edculo \u00a035 \u00a0de \u00a0la Constituci\u00f3n \u00a0Pol\u00edtica, \u00a0el art\u00edculo \u00a018 \u00a0del C\u00f3digo Penal (Ley \u00a0599 \u00a0 de \u00a0 2000) \u00a0y \u00a0el \u00a0art\u00edculo \u00a0490 del C\u00f3digo \u00a0de \u00a0 \u00a0 \u00a0Procedimiento \u00a0 \u00a0 Penal \u00a0 \u00a0 (Ley \u00a0906 de \u00a02004), \u00a0la \u00a0extradici\u00f3n \u00a0de colombianos por \u00a0nacimiento \u00a0 \u00a0se \u00a0 puede \u00a0 conceder, \u00a0 conforme \u00a0a los tratados p\u00fablicos o en \u00a0su \u00a0defecto \u00a0con \u00a0la \u00a0ley, \u00a0por \u00a0delitos \u00a0considerados \u00a0como \u00a0tales dentro de la \u00a0legislaci\u00f3n \u00a0penal interna que hayan sido cometidos en el exterior a partir del \u00a017 \u00a0de \u00a0diciembre \u00a0de \u00a01997, fecha en la que entr\u00f3 a \u00a0regir \u00a0el \u00a0acto \u00a0legislativo \u00a0que modific\u00f3 la citada \u00a0norma constitucional. \u00a0\u00a0<\/p>\n<p>Debido a que no \u00a0existe \u00a0 tratado \u00a0 de \u00a0 extradici\u00f3n \u00a0aplicable \u00a0entre \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Norteam\u00e9rica \u00a0y \u00a0Colombia, \u00a0seg\u00fan \u00a0lo \u00a0inform\u00f3 \u00a0el \u00a0Ministerio \u00a0de Relaciones \u00a0Exteriores, \u00a0 \u00a0 y \u00a0 \u00a0 dado \u00a0 \u00a0que \u00a0 \u00a0los \u00a0 \u00a0 hechos \u00a0 \u00a0 ocurrieron \u00a0 \u00a0con \u00a0posterioridad \u00a0al \u00a017 \u00a0de \u00a0diciembre \u00a0de \u00a01997 \u00a0hasta \u00a0agosto de 2008 \u00a0inclusive, \u00a0como \u00a0se \u00a0afirma \u00a0en la \u00a0acusaci\u00f3n, \u00a0 este \u00a0 tr\u00e1mite \u00a0 de \u00a0 extradici\u00f3n \u00a0 se \u00a0 rige \u00a0por \u00a0el \u00a0C\u00f3digo \u00a0de \u00a0 \u00a0 \u00a0Procedimiento \u00a0 \u00a0 Penal, \u00a0 \u00a0 (Ley \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0906 \u00a0 \u00a0 \u00a0 de \u00a0 \u00a0 \u00a02004). \u00a0\u00a0<\/p>\n<p>De \u00a0 conformidad \u00a0 con \u00a0 el \u00a0 art\u00edculo \u00a0502 \u00a0 de \u00a0la \u00a0Ley \u00a0906 \u00a0de \u00a02004 \u00a0(C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal), la \u00a0Corte \u00a0 Suprema \u00a0 de \u00a0 Justicia \u00a0debe \u00a0fundamentar \u00a0su \u00a0concepto \u00a0exclusivamente \u00a0en \u00a0la validez formal de \u00a0la \u00a0 \u00a0 documentaci\u00f3n \u00a0 \u00a0 presentada; \u00a0 en \u00a0la \u00a0demostraci\u00f3n \u00a0 \u00a0plena \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0identidad \u00a0 \u00a0del \u00a0 \u00a0solicitado; \u00a0 \u00a0en \u00a0el \u00a0principio de la doble \u00a0incriminaci\u00f3n; \u00a0en la equivalencia de la providencia \u00a0dictada \u00a0en el extranjero; \u00a0y, \u00a0en el cumplimiento de \u00a0lo \u00a0previsto \u00a0en los tratados p\u00fablicos, cuando fuere \u00a0el caso. \u00a0\u00a0<\/p>\n<p>La \u00a0Sala, en consecuencia, abordar\u00e1 en el \u00a0orden \u00a0enunciado \u00a0el \u00a0estudio \u00a0de \u00a0cada \u00a0uno \u00a0de \u00a0estos \u00a0requisitos, orientada a \u00a0establecer la procedencia de la solicitud de extradici\u00f3n. \u00a0\u00a0<\/p>\n<p>2. \u00a0Validez \u00a0formal de la documentaci\u00f3n presentada \u00a0\u00a0<\/p>\n<p>Como \u00a0lo \u00a0dispone \u00a0el \u00a0art\u00edculo \u00a0495 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0Ley \u00a0906 de 2004, para conceder u ofrecer la \u00a0extradici\u00f3n \u00a0 de \u00a0una \u00a0persona \u00a0la \u00a0solicitud \u00a0debe \u00a0ser \u00a0presentada \u00a0por \u00a0v\u00eda \u00a0diplom\u00e1tica \u00a0o en casos excepcionales por la consular o de gobierno a gobierno, \u00a0adjuntando: \u00a0 \u00a0i) \u00a0 \u00a0copia \u00a0 \u00a0o \u00a0 \u00a0transcripci\u00f3n \u00a0aut\u00e9ntica \u00a0de \u00a0la \u00a0sentencia, de la resoluci\u00f3n de acusaci\u00f3n o su equivalente; \u00a0ii) \u00a0indicaci\u00f3n exacta de los actos que determinaron la solicitud y del lugar y \u00a0la \u00a0fecha \u00a0en que fueron ejecutados; iii) todos los datos que se posean y sirvan \u00a0para \u00a0establecer \u00a0la \u00a0plena \u00a0identidad \u00a0de \u00a0la \u00a0persona \u00a0reclamada; \u00a0y iv) copia \u00a0aut\u00e9ntica de las disposiciones penales aplicables para el caso. \u00a0\u00a0<\/p>\n<p>Tales \u00a0documentos \u00a0deben \u00a0ser expedidos de \u00a0acuerdo \u00a0con \u00a0la \u00a0forma se\u00f1alada por la legislaci\u00f3n del Estado requirente y se \u00a0traducir\u00e1n al castellano, si fuere necesario. \u00a0\u00a0<\/p>\n<p>El \u00a0 art\u00edculo \u00a0 259 \u00a0 del \u00a0 C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Civil, \u00a0modificado \u00a0por el art\u00edculo 1\u00ba, numeral 118 del Decreto \u00a02282 \u00a0 de \u00a0 1989, \u00a0estipula \u00a0que \u00a0\u201cLos \u00a0documentos \u00a0p\u00fablicos \u00a0otorgados \u00a0en \u00a0el \u00a0pa\u00eds extranjero por funcionario de \u00e9ste o con su \u00a0intervenci\u00f3n, \u00a0deber\u00e1n \u00a0presentarse \u00a0debidamente autenticados por el c\u00f3nsul o \u00a0agente \u00a0diplom\u00e1tico \u00a0de \u00a0la \u00a0Rep\u00fablica, \u00a0y en su defecto por el de una naci\u00f3n \u00a0amiga, \u00a0lo \u00a0cual hace presumir que se otorgaron conforme a la ley del respectivo \u00a0pa\u00eds. \u00a0La \u00a0firma \u00a0del \u00a0c\u00f3nsul \u00a0o \u00a0agente diplom\u00e1tico se abonar\u00e1 por el\u00a0 \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores \u00a0de \u00a0Colombia, \u00a0y \u00a0si se trata de agentes \u00a0consulares \u00a0de \u00a0un \u00a0pa\u00eds \u00a0amigo, se autenticar\u00e1 previamente por el funcionario \u00a0competente del mismo y los de \u00e9ste por el C\u00f3nsul colombiano.\u201d \u00a0\u00a0<\/p>\n<p>Aquellas \u00a0exigencias \u00a0fueron adecuadamente \u00a0observadas \u00a0por \u00a0el\u00a0 Gobierno de los Estados Unidos de Norteam\u00e9rica, pues, \u00a0por \u00a0v\u00eda \u00a0diplom\u00e1tica, \u00a0present\u00f3 \u00a0la \u00a0solicitud \u00a0a \u00a0trav\u00e9s de su Embajada en \u00a0nuestro \u00a0pa\u00eds \u00a0al \u00a0Ministerio \u00a0de \u00a0Relaciones \u00a0Exteriores; \u00a0anex\u00f3 \u00a0copia de la \u00a0Resoluci\u00f3n \u00a0 \u00a0de \u00a0 Acusaci\u00f3n \u00a0 No. \u00a0 08-CRIM \u00a01003, \u00a0dictada el 16 \u00a0 de \u00a0 octubre \u00a0de \u00a02008, \u00a0en \u00a0la \u00a0Corte \u00a0 Distrital \u00a0 de \u00a0los \u00a0Estados \u00a0Unidos \u00a0para \u00a0el \u00a0Distrito \u00a0Sur \u00a0de \u00a0Nueva \u00a0York, \u00a0 contra \u00a0 \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 LE\u00d3N \u00a0NI\u00d1O \u00a0 por \u00a0 delitos \u00a0federales \u00a0de narc\u00f3ticos. \u00a0\u00a0<\/p>\n<p>Con \u00a0las notas \u00a0diplom\u00e1ticas \u00a0 \u00a0a \u00a0 \u00a0trav\u00e9s \u00a0 \u00a0de \u00a0 las \u00a0 cuales \u00a0 solicit\u00f3 \u00a0 la \u00a0 detenci\u00f3n \u00a0provisional \u00a0 \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 \u00a0 formaliz\u00f3 \u00a0 \u00a0 \u00a0 la \u00a0reclamaci\u00f3n, \u00a0y \u00a0con \u00a0las declaraciones rendidas en \u00a0apoyo \u00a0de \u00a0la \u00a0solicitud por Marshall A. Camp, Fiscal \u00a0Auxiliar \u00a0 de \u00a0 los \u00a0 Estados \u00a0 Unidos \u00a0 en \u00a0el \u00a0Distrito \u00a0Meridional \u00a0de \u00a0Nueva \u00a0York \u00a0 y \u00a0Kenneth \u00a0 \u00a0E. \u00a0 \u00a0Mckindra, \u00a0 \u00a0Agente \u00a0Especial de la Administraci\u00f3n para el\u00a0 Control \u00a0de \u00a0Drogas \u00a0(DEA), \u00a0se \u00a0determinan las conductas que \u00a0fundamentan \u00a0 la \u00a0 reclamaci\u00f3n, \u00a0especificando \u00a0las \u00a0circunstancias \u00a0de \u00a0modo, \u00a0tiempo \u00a0y lugar de realizaci\u00f3n de los diversos actos \u00a0que \u00a0 integran \u00a0 la \u00a0 ejecuci\u00f3n \u00a0 de \u00a0 cada \u00a0 uno \u00a0de \u00a0los \u00a0delitos. \u00a0\u00a0<\/p>\n<p>Con \u00a0dicha \u00a0informaci\u00f3n no s\u00f3lo pone en \u00a0evidencia \u00a0la \u00a0exactitud \u00a0de \u00a0las conductas imputadas, el lugar y la fecha de su \u00a0ejecuci\u00f3n, \u00a0sino \u00a0que \u00a0demuestra \u00a0que \u00a0los \u00a0hechos \u00a0con los cuales se pretenden \u00a0comprobar \u00a0sucedieron \u00a0en \u00a0el \u00a0pa\u00eds \u00a0requirente, \u00a0cumpliendo de esta \u00a0manera \u00a0la \u00a0exigencia \u00a0del \u00a0art\u00edculo 35 de la Constituci\u00f3n \u00a0Pol\u00edtica, \u00a0consistente \u00a0en \u00a0que \u00a0la \u00a0extradici\u00f3n \u00a0de \u00a0colombianos por \u00a0 nacimiento \u00a0se \u00a0conceder\u00e1 \u00a0por \u00a0delitos cometidos en el exterior. \u00a0\u00a0<\/p>\n<p>De \u00a0otra parte, como se ver\u00e1, los anexos \u00a0permiten \u00a0establecer \u00a0la \u00a0identidad del reclamado, y \u00a0con \u00a0la \u00a0transcripci\u00f3n de \u00a0las \u00a0disposiciones \u00a0de \u00a0las leyes de Estados Unidos supuestamente transgredidas, \u00a0se establece la doble incriminaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Aquellos \u00a0documentos \u00a0fueron autenticados \u00a0seg\u00fan \u00a0lo dispuesto en el art\u00edculo 259 del C\u00f3digo de Procedimiento Civil, por \u00a0lo \u00a0 cual \u00a0 se \u00a0 presume \u00a0que \u00a0fueron \u00a0otorgados \u00a0de \u00a0conformidad con \u00a0el \u00a0ordenamiento jur\u00eddico de los Estados Unidos; siendo, por \u00a0tanto, factible admitirlos como medios de prueba en este tr\u00e1mite. \u00a0\u00a0<\/p>\n<p>En \u00a0 \u00a0 \u00a0efecto, \u00a0 \u00a0 \u00a0Thomas \u00a0C. \u00a0Black, Director Asociado de \u00a0la \u00a0Oficina \u00a0de \u00a0Asuntos Internacionales, Divisi\u00f3n de lo Penal, Departamento de \u00a0Justicia \u00a0de \u00a0los \u00a0Estados Unidos de Norteam\u00e9rica, certific\u00f3 que copias fieles \u00a0de \u00a0los \u00a0testimonios \u00a0rendidos \u00a0por Marshall A. Camp, \u00a0Fiscal \u00a0Auxiliar \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0en \u00a0el \u00a0Distrito Meridional de Nueva \u00a0York \u00a0 y \u00a0 Kenneth \u00a0E. \u00a0Mckindra, \u00a0Agente Especial \u00a0de \u00a0la \u00a0Administraci\u00f3n \u00a0para \u00a0el\u00a0 \u00a0Control \u00a0de \u00a0Drogas (DEA), se \u00a0mantienen \u00a0en \u00a0los \u00a0archivos \u00a0oficiales \u00a0del \u00a0Departamento \u00a0de \u00a0Justicia \u00a0 \u00a0 de \u00a0 \u00a0Washington \u00a0 \u00a0D.C., \u00a0 de \u00a0 los \u00a0 Estados \u00a0 Unidos \u00a0 de \u00a0 Norteam\u00e9rica \u00a0 (Folio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 128 \u00a0carpeta \u00a0anexa). \u00a0\u00a0<\/p>\n<p>El \u00a0Procurador \u00a0de \u00a0los \u00a0Estados \u00a0Unidos, \u00a0Eric \u00a0H. Holder Jr., hizo \u00a0constar \u00a0que \u00a0para \u00a0ese \u00a0entonces, \u00a0Thomas C. Black, \u00a0desempe\u00f1aba \u00a0el \u00a0cargo \u00a0de Director Asociado, de la \u00a0Oficina \u00a0 de \u00a0 Asuntos \u00a0Internacionales, \u00a0de \u00a0la \u00a0Divisi\u00f3n \u00a0de \u00a0lo \u00a0Penal, \u00a0del \u00a0Departamento \u00a0de \u00a0Justicia \u00a0de los Estados Unidos, en Washington D.C., quien con \u00a0ese \u00a0prop\u00f3sito \u00a0hizo estampar el sello del Departamento de Justicia y solicit\u00f3 \u00a0al \u00a0Director \u00a0Adjunto \u00a0de \u00a0la \u00a0Oficina \u00a0de \u00a0Asuntos \u00a0Internacionales, \u00a0Divisi\u00f3n \u00a0de \u00a0lo Penal que diera fe \u00a0de \u00a0 \u00a0 \u00a0su \u00a0 \u00a0 \u00a0firma \u00a0 \u00a0 (Folio \u00a0 \u00a0 129 \u00a0carpeta \u00a0anexa). \u00a0\u00a0<\/p>\n<p>La \u00a0Secretaria \u00a0de \u00a0Estado, \u00a0Hillary \u00a0 \u00a0 \u00a0 \u00a0Rodham \u00a0Clinton, certific\u00f3 que al documento \u00a0anexo \u00a0se \u00a0le \u00a0fij\u00f3 el sello del Departamento de Justicia de los Estados Unidos \u00a0de \u00a0Am\u00e9rica, \u00a0en \u00a0testimonio de lo cual hizo fijar el sello del Departamento de \u00a0Estado \u00a0y \u00a0que \u00a0el Funcionario Auxiliar de Autenticaciones de dicho Departamento \u00a0en \u00a0 Washington, \u00a0 Sonya \u00a0 N. \u00a0 Johnson, \u00a0suscribiera \u00a0su nombre (Folio \u00a0196 \u00a0carpeta \u00a0 anexa). \u00a0\u00a0<\/p>\n<p>El \u00a0C\u00f3nsul \u00a0de \u00a0Colombia \u00a0en Washington, \u00a0Julio \u00a0C\u00e9sar Aldana Bula, certific\u00f3 que es aut\u00e9ntica la firma de Sonya \u00a0 \u00a0N. \u00a0 Johnson, \u00a0 y \u00a0a \u00a0su \u00a0vez, \u00a0la \u00a0firma \u00a0del \u00a0C\u00f3nsul fue abonada por el Jefe de \u00a0Autenticaciones \u00a0 del \u00a0 Ministerio \u00a0 de \u00a0 Relaciones \u00a0 Exteriores \u00a0 (Folio \u00a0197 \u00a0carpeta \u00a0 anexa). \u00a0\u00a0<\/p>\n<p>Los \u00a0 mencionados \u00a0 documentos \u00a0 fueron \u00a0traducidos \u00a0 al \u00a0 castellano \u00a0 por \u00a0 la \u00a0 Embajada \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>Se \u00a0verifica de esa manera que se re\u00fanen \u00a0las \u00a0exigencias del art\u00edculo 495 del C\u00f3digo de Procedimiento Penal, Ley 906 de \u00a02004, \u00a0por \u00a0lo \u00a0cual \u00a0se \u00a0satisface \u00a0el \u00a0requisito \u00a0de \u00a0la \u00a0validez formal de la \u00a0documentaci\u00f3n presentada con la solicitud de extradici\u00f3n. \u00a0\u00a0<\/p>\n<p>3. \u00a0Demostraci\u00f3n plena de la identidad del solicitado \u00a0\u00a0<\/p>\n<p>La \u00a0 informaci\u00f3n \u00a0 que \u00a0 contiene \u00a0 la \u00a0documentaci\u00f3n \u00a0aportada para el presente tr\u00e1mite permite a la Sala deducir que \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 \u00a0LE\u00d3N \u00a0 NI\u00d1O, \u00a0privado \u00a0de \u00a0la libertad con fines de extradici\u00f3n, es la misma \u00a0persona \u00a0 que \u00a0 es \u00a0 requerida \u00a0 por \u00a0el \u00a0Gobierno \u00a0de \u00a0los \u00a0Estados \u00a0Unidos \u00a0de \u00a0Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0se \u00a0infiere valorando conjuntamente \u00a0los \u00a0datos suministrados por el pa\u00eds requirente en las notas diplom\u00e1ticas y en \u00a0los \u00a0 testimonios \u00a0rendidos \u00a0en \u00a0apoyo \u00a0de \u00a0la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n; \u00a0lo \u00a0consignado \u00a0en \u00a0la orden y en el informe sobre la materializaci\u00f3n de la captura \u00a0de \u00a0 JOS\u00c9 \u00a0 DE \u00a0 JES\u00daS \u00a0 LE\u00d3N \u00a0NI\u00d1O, \u00a0y \u00a0la \u00a0actitud \u00a0asumida \u00a0por \u00a0\u00e9ste \u00a0en \u00a0el curso del tr\u00e1mite, \u00a0consistente \u00a0 en \u00a0 otorgar \u00a0 poder \u00a0a \u00a0su \u00a0abogado \u00a0de \u00a0confianza \u00a0para \u00a0que \u00a0lo \u00a0asistiera. \u00a0\u00a0<\/p>\n<p>La \u00a0 Nota \u00a0 Verbal \u00a0 No. \u00a0 3302 \u00a0del \u00a01\u00ba \u00a0 \u00a0de \u00a0 \u00a0 \u00a0diciembre \u00a0 \u00a0 de \u00a0 2008, \u00a0mediante \u00a0la \u00a0cual \u00a0fue \u00a0solicitada \u00a0la \u00a0detenci\u00f3n \u00a0provisional \u00a0con \u00a0fines \u00a0de \u00a0extradici\u00f3n, \u00a0hace saber que el requerido se llama \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 \u00a0LE\u00d3N \u00a0 NI\u00d1O, ciudadano \u00a0colombiano, \u00a0 nacido \u00a0 el \u00a0 29 \u00a0de \u00a0abril \u00a0de \u00a01956 \u00a0en Colombia, y \u00a0es \u00a0portador \u00a0de \u00a0la \u00a0c\u00e9dula \u00a0de \u00a0ciudadan\u00eda No. 19.305.030. \u00a0\u00a0<\/p>\n<p>La \u00a0 Nota \u00a0 Verbal \u00a0 No. \u00a0 0621 \u00a0del \u00a0 19 \u00a0de \u00a0marzo \u00a0de 2009, \u00a0que \u00a0formaliz\u00f3 \u00a0la solicitud, las \u00a0declaraciones \u00a0rendidas \u00a0en apoyo, la resoluci\u00f3n que orden\u00f3 la captura emitida \u00a0por \u00a0el \u00a0Despacho \u00a0del \u00a0Fiscal \u00a0General \u00a0de \u00a0la Naci\u00f3n, reiteran y ratifican la \u00a0informaci\u00f3n \u00a0relativa \u00a0a \u00a0la \u00a0identidad \u00a0del \u00a0ciudadano \u00a0requerido, la cual fue \u00a0constatada \u00a0por los agentes de la Polic\u00eda Judicial que realizaron la captura de \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 \u00a0LE\u00d3N \u00a0 NI\u00d1O, con fines de extradici\u00f3n. \u00a0\u00a0<\/p>\n<p>Con motivo de la captura se confeccionaron \u00a0las \u00a0actas \u00a0respectivas \u00a0y \u00a0en la notificaci\u00f3n de los derechos del capturado la \u00a0persona \u00a0detenida dijo llamarse e identificarse con los mismos nombres y c\u00e9dula \u00a0reportados \u00a0por las autoridades extranjeras, actitud que ha sostenido a lo largo \u00a0del \u00a0 \u00a0tr\u00e1mite, \u00a0 sin \u00a0 que \u00a0 la \u00a0 defensa \u00a0 haya \u00a0 formulado \u00a0 cuestionamiento \u00a0alguno. \u00a0\u00a0<\/p>\n<p>Se \u00a0 evidencia \u00a0as\u00ed \u00a0que \u00a0JOS\u00c9 \u00a0DE \u00a0JES\u00daS \u00a0LE\u00d3N NI\u00d1O, persona \u00a0que \u00a0 fue \u00a0 aprehendida \u00a0y \u00a0permanece \u00a0privada \u00a0de \u00a0la \u00a0libertad \u00a0con \u00a0fines \u00a0de \u00a0extradici\u00f3n, \u00a0 es \u00a0la \u00a0misma \u00a0que \u00a0reclama \u00a0en \u00a0tal \u00a0condici\u00f3n el Gobierno de \u00a0los \u00a0 \u00a0 Estados \u00a0 \u00a0 Unidos \u00a0 \u00a0 de \u00a0 \u00a0Am\u00e9rica. \u00a0\u00a0<\/p>\n<p>4. Principio de \u00a0la doble incriminaci\u00f3n \u00a0\u00a0<\/p>\n<p>Establece el numeral 1\u00b0 del art\u00edculo 493 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0Ley \u00a0906 \u00a0de \u00a02004, que para conceder u \u00a0ofrecer \u00a0la \u00a0extradici\u00f3n \u00a0se \u00a0requiere que \u00a0el \u00a0hecho \u00a0que \u00a0la motive tambi\u00e9n est\u00e9 previsto en Colombia \u00a0como \u00a0 \u00a0 \u00a0delito \u00a0 \u00a0 \u00a0y \u00a0 \u00a0 \u00a0sea \u00a0 \u00a0 reprimido \u00a0con \u00a0una sanci\u00f3n privativa de la libertad cuyo m\u00ednimo \u00a0no sea inferior a cuatro (4) a\u00f1os. \u00a0\u00a0<\/p>\n<p>Dicho \u00a0presupuesto \u00a0se \u00a0cumple \u00a0frente al \u00a0ciudadano \u00a0 colombiano \u00a0 JOS\u00c9 \u00a0 DE \u00a0 JES\u00daS \u00a0LE\u00d3N \u00a0NI\u00d1O, \u00a0en \u00a0relaci\u00f3n \u00a0con los cargos por los que es \u00a0requerido, \u00a0 \u00a0por \u00a0 \u00a0cuanto \u00a0 \u00a0incluye \u00a0el \u00a0equivalente \u00a0en \u00a0Colombia \u00a0a \u00a0los \u00a0delitos \u00a0de \u00a0concierto \u00a0para \u00a0delinquir con fines de \u00a0narcotr\u00e1fico,\u00a0 \u00a0y \u00a0tr\u00e1fico, \u00a0 \u00a0 fabricaci\u00f3n \u00a0 \u00a0 o \u00a0 \u00a0 porte \u00a0 \u00a0 de \u00a0estupefacientes.\u00a0 \u00a0\u00a0<\/p>\n<p>En \u00a0la Acusaci\u00f3n formal No. 08-CRIM \u00a01003, \u00a0dictada el 16 \u00a0 de \u00a0 octubre \u00a0de \u00a02008, \u00a0en \u00a0la \u00a0Corte \u00a0 Distrital \u00a0 de \u00a0los \u00a0Estados \u00a0Unidos \u00a0para \u00a0el \u00a0Distrito \u00a0Sur \u00a0de \u00a0Nueva \u00a0York, \u00a0 se \u00a0imputan \u00a0al \u00a0requerido los siguientes cargos: \u00a0\u00a0<\/p>\n<p>\u201cCARGO \u00a0UNO \u00a0\u00a0<\/p>\n<p>El gran jurado imputa: \u00a0<\/p>\n<p>1. Inici\u00e1ndose \u00a0en \u00a0el \u00a0a\u00f1o \u00a02000, \u00a0o \u00a0en una fecha aproximada, hasta octubre de 2008, o en una \u00a0fecha \u00a0aproximada, \u00a0en \u00a0el \u00a0Distrito Meridional de Nueva York y en otras partes, \u00a0(\u2026), \u00a0JOS\u00c9 \u00a0DE \u00a0JES\u00daS LE\u00d3N NI\u00d1O, alias \u201cJos\u00e9 \u00a0Le\u00f3n\u201d \u00a0(\u2026), \u00a0los \u00a0acusados, y otros conocidos y \u00a0desconocidos, \u00a0ilegal \u00a0e \u00a0intencionalmente \u00a0y \u00a0con \u00a0conocimiento \u00a0se combinaron, \u00a0concertaron, \u00a0se \u00a0asociaron \u00a0y \u00a0acordaron conjuntamente y uno con otro violar la \u00a0legislaci\u00f3n contra narc\u00f3ticos de los Estados Unidos. \u00a0\u00a0<\/p>\n<p>2. Fue parte y \u00a0objeto \u00a0de \u00a0tal \u00a0concierto que (\u2026), JOS\u00c9 DE JES\u00daS \u00a0LE\u00d3N \u00a0NI\u00d1O, \u00a0alias \u00a0\u201cJos\u00e9 Le\u00f3n\u201d (\u2026), \u00a0 los \u00a0 acusados, \u00a0 y \u00a0 otros \u00a0 conocidos \u00a0y \u00a0desconocidos, \u00a0importar\u00edan \u00a0y, de hecho, importaron a los Estados Unidos de un lugar fuera del \u00a0mismo, \u00a0una \u00a0sustancia \u00a0controlada, \u00a0a \u00a0saber, \u00a0un kilogramo y m\u00e1s de mezclas y \u00a0sustancias \u00a0que \u00a0conten\u00edan \u00a0una cantidad perceptible de hero\u00edna, en violaci\u00f3n \u00a0de \u00a0las \u00a0Secciones \u00a0812, \u00a0952 \u00a0(a), \u00a0960 \u00a0(a) \u00a0(1) \u00a0y\u00a0 \u00a0960 \u00a0(b) \u00a0(1) \u00a0(A), del T\u00edtulo 21\u00a0 del \u00a0C\u00f3digo de los Estados Unidos. \u00a0\u00a0<\/p>\n<p>3. Adem\u00e1s, fue \u00a0parte \u00a0y \u00a0objeto de tal concierto que (\u2026), JOS\u00c9 DE \u00a0JES\u00daS \u00a0 LE\u00d3N \u00a0 NI\u00d1O, \u00a0 alias \u00a0 \u201cJos\u00e9 \u00a0Le\u00f3n\u201d \u00a0(\u2026), \u00a0 los \u00a0 acusados, \u00a0 y \u00a0 otros \u00a0 conocidos \u00a0y \u00a0desconocidos, \u00a0estando \u00a0fuera \u00a0de \u00a0la \u00a0jurisdicci\u00f3n \u00a0territorial de los Estados \u00a0Unidos, \u00a0distribuir\u00edan \u00a0y, \u00a0de hecho, distribuyeron una sustancia controlada, a \u00a0saber, \u00a0un \u00a0kilogramo o m\u00e1s de mezclas y sustancias que conten\u00edan una cantidad \u00a0perceptible \u00a0de \u00a0hero\u00edna, \u00a0con \u00a0conocimiento \u00a0e intenci\u00f3n de que tal sustancia \u00a0ser\u00eda \u00a0importada \u00a0ilegalmente \u00a0a \u00a0los \u00a0Estados \u00a0Unidos o a aguas adentro de una \u00a0distancia \u00a0de \u00a012\u00a0 \u00a0millas de la costa de los Estados Unidos, en violaci\u00f3n \u00a0de \u00a0las \u00a0Secciones \u00a0812, 959 (a) y 960 (b) (1) (A) del T\u00edtulo 21 del C\u00f3digo de \u00a0los Estados Unidos. \u00a0\u00a0<\/p>\n<p>CARGO \u00a0 \u00a0 \u00a0 \u00a0 DOS \u00a0\u00a0<\/p>\n<p>El gran jurado adem\u00e1s imputa: \u00a0<\/p>\n<p>5. Inici\u00e1ndose en el a\u00f1o 2000, o en una \u00a0fecha \u00a0aproximada, \u00a0hasta \u00a0octubre \u00a0de \u00a02008, \u00a0o \u00a0en una fecha aproximada, en el \u00a0Distrito \u00a0Meridional \u00a0de \u00a0Nueva \u00a0York \u00a0y en otras partes, (\u2026), JOS\u00c9 DE JES\u00daS \u00a0LE\u00d3N \u00a0NI\u00d1O, \u00a0alias \u00a0\u201cJos\u00e9 Le\u00f3n\u201d (\u2026), \u00a0los \u00a0acusados, \u00a0y otros conocidos y desconocidos, ilegal e \u00a0intencionalmente \u00a0y \u00a0con conocimiento se combinaron, concertaron, se asociaron y \u00a0acordaron \u00a0 conjuntamente \u00a0 y \u00a0 uno \u00a0con \u00a0otro \u00a0violar \u00a0la \u00a0legislaci\u00f3n \u00a0contra \u00a0narc\u00f3ticos de los Estados Unidos.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>6. \u00a0Fue \u00a0parte y objeto del concierto que \u00a0(\u2026), \u00a0JOS\u00c9 \u00a0DE \u00a0JES\u00daS LE\u00d3N NI\u00d1O, alias \u201cJos\u00e9 \u00a0Le\u00f3n\u201d \u00a0(\u2026), \u00a0los \u00a0acusados, y otros conocidos y \u00a0desconocidos, \u00a0distribuir\u00edan \u00a0y \u00a0de hecho distribuyeron y poseer\u00edan y de hecho \u00a0poseyeron, \u00a0con \u00a0intenci\u00f3n de distribuir, una sustancia controlada, a saber, un \u00a0kilogramo \u00a0 y \u00a0 m\u00e1s \u00a0de \u00a0mezclas \u00a0y \u00a0sustancias \u00a0que \u00a0conten\u00edan \u00a0una \u00a0cantidad \u00a0perceptible \u00a0de \u00a0hero\u00edna, en violaci\u00f3n de las Secciones 812, 841 (a) (1) y 841 \u00a0(b) \u00a0(1) \u00a0(A) \u00a0(i) del T\u00edtulo 21 del C\u00f3digo de los Estados Unidos.\u201d. \u00a0\u00a0<\/p>\n<p>El \u00a0delito \u00a0de \u00a0concierto \u00a0para infringir \u00a0las \u00a0 \u00a0 leyes \u00a0 \u00a0 antinarc\u00f3ticos \u00a0 \u00a0de \u00a0los \u00a0Estados \u00a0Unidos, \u00a0endilgado a \u00a0JOS\u00c9 \u00a0 \u00a0DE \u00a0 \u00a0JES\u00daS \u00a0 \u00a0LE\u00d3N \u00a0 NI\u00d1O, \u00a0es \u00a0tambi\u00e9n \u00a0punible en Colombia, pues configura el injusto de \u00a0concierto \u00a0para delinquir \u00a0previsto \u00a0en el art\u00edculo 340 del C\u00f3digo Penal, Ley 599 de 2000, modificado por \u00a0la \u00a0Ley \u00a0733 de 2002, que sanciona a quienes se concierten con el fin de cometer \u00a0delitos \u00a0con prisi\u00f3n de 4 a 9 a\u00f1os. Sin embargo, esta pena fue incrementada en \u00a0la \u00a0tercera \u00a0parte \u00a0por \u00a0la \u00a0Ley 890 de 2004, quedando sancionado, entonces, con \u00a0prisi\u00f3n de 6 a 12 a\u00f1os.\u00a0 \u00a0\u00a0<\/p>\n<p>El \u00a0delito \u00a0de \u00a0concierto \u00a0para delinquir \u00a0previsto \u00a0en \u00a0el \u00a0art\u00edculo \u00a0340 del C\u00f3digo Penal, Ley 599 de 2000, se sanciona \u00a0con \u00a0pena de prisi\u00f3n de 8 \u00a0a \u00a018 \u00a0a\u00f1os, \u00a0cuando \u00a0el \u00a0acuerdo \u00a0se dirija al tr\u00e1fico de estupefacientes, de \u00a0acuerdo \u00a0 con \u00a0 lo \u00a0 dispuesto \u00a0 por \u00a0 el \u00a0 art\u00edculo \u00a019 \u00a0de \u00a0la \u00a0Ley \u00a01121 \u00a0de \u00a02006. \u00a0\u00a0<\/p>\n<p>Como \u00a0se \u00a0observa, \u00a0la \u00a0conducta a que se \u00a0refiere \u00a0el primer cargo, concierto para infringir las leyes antinarc\u00f3ticos, se \u00a0encuentra \u00a0tipificada \u00a0como \u00a0delito \u00a0en \u00a0Colombia, y se sanciona con prisi\u00f3n no \u00a0inferior a cuatro a\u00f1os. \u00a0\u00a0<\/p>\n<p>De \u00a0igual \u00a0manera, \u00a0el \u00a0art\u00edculo 376 del \u00a0C\u00f3digo \u00a0 Penal, \u00a0 Ley \u00a0 599 \u00a0 de \u00a0 2000, \u00a0prev\u00e9 \u00a0y \u00a0sanciona \u00a0el \u00a0tr\u00e1fico, \u00a0fabricaci\u00f3n \u00a0o \u00a0porte \u00a0de estupefacientes con \u00a0 pena \u00a0 de \u00a0 prisi\u00f3n \u00a0de \u00a0ocho \u00a0(8) \u00a0a \u00a0veinte \u00a0(20) \u00a0a\u00f1os. \u00a0\u00a0<\/p>\n<p>Debe \u00a0tenerse \u00a0en \u00a0cuenta que la sanci\u00f3n \u00a0penal \u00a0se\u00f1alada \u00a0para \u00a0el \u00a0tr\u00e1fico, \u00a0fabricaci\u00f3n \u00a0o \u00a0porte de estupefacientes \u00a0contemplado \u00a0en \u00a0el \u00a0art\u00edculo \u00a0anterior, \u00a0fue incrementada en una tercera parte \u00a0conforme \u00a0al \u00a0art\u00edculo \u00a014 \u00a0de \u00a0la \u00a0Ley \u00a0890 \u00a0de 2004, por lo que la pena ser\u00e1 \u00a0entonces, \u00a0 de \u00a0 ciento \u00a0 veintiocho \u00a0 (128) \u00a0 a \u00a0 trescientos \u00a0 sesenta \u00a0 (360) \u00a0meses \u00a0y \u00a0multa \u00a0de \u00a0mil \u00a0trescientos \u00a0 \u00a0treinta \u00a0 \u00a0y \u00a0 tres \u00a0 punto \u00a0 treinta \u00a0 y \u00a0 tres \u00a0 (1.333.33) \u00a0 \u00a0 a \u00a0 \u00a0 cincuenta \u00a0 \u00a0mil \u00a0(50.000) \u00a0 \u00a0salarios \u00a0m\u00ednimos legales mensuales vigentes. \u00a0\u00a0<\/p>\n<p>En \u00a0 \u00a0consecuencia, \u00a0 \u00a0surge \u00a0evidente \u00a0que \u00a0frente \u00a0a \u00a0estos \u00a0comportamientos \u00a0 \u00a0converge \u00a0 la \u00a0 condici\u00f3n \u00a0 de \u00a0 ser \u00a0 delictivos \u00a0 en \u00a0 Colombia \u00a0 y \u00a0 estar \u00a0 \u00a0 \u00a0 sancionados \u00a0 \u00a0 \u00a0 \u00a0con \u00a0 \u00a0 \u00a0 prisi\u00f3n \u00a0 no \u00a0 menor \u00a0 de \u00a0 cuatro \u00a0a\u00f1os, \u00a0por \u00a0tanto \u00a0se \u00a0cumple \u00a0de \u00a0 este \u00a0 modo \u00a0 el \u00a0 principio \u00a0 de \u00a0 la \u00a0 doble \u00a0incriminaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Respecto \u00a0del \u00a0decomiso \u00a0planteado \u00a0en la \u00a0acusaci\u00f3n, \u00a0con base en el T\u00edtulo 21, Secciones 853 \u00a0y \u00a0970 del C\u00f3digo de los Estados Unidos, la cual busca el decomiso de todos los \u00a0bienes \u00a0que \u00a0se \u00a0hayan \u00a0derivado \u00a0de \u00a0ingresos \u00a0obtenidos \u00a0como \u00a0resultado de la \u00a0comisi\u00f3n \u00a0 de \u00a0 los \u00a0 anteriores \u00a0 delitos, \u00a0si \u00a0dichos \u00a0bienes \u00a0no \u00a0estuvieren \u00a0disponibles, \u00a0y \u00a0que \u00a0las \u00a0normas \u00a0citadas permiten que otros bienes del acusado \u00a0sean \u00a0decomisados, \u00a0es preciso se\u00f1alar que esta menci\u00f3n no puede ser entendida \u00a0en estricto sentido como un cargo. \u00a0\u00a0<\/p>\n<p>En \u00a0efecto, \u00a0como \u00a0lo \u00a0ha \u00a0expresado esta \u00a0Corporaci\u00f3n \u00a0respecto \u00a0de \u00a0situaciones \u00a0semejantes1, \u00a0 \u00a0 \u00a0 \u00a0 al \u00a0precisar \u00a0que, \u00a0el \u00a0se\u00f1alamiento \u00a0de \u00a0la \u00a0pena de decomiso no \u00a0comporta \u00a0imputaci\u00f3n \u00a0alguna; \u00a0a \u00a0lo \u00a0sumo \u00a0es \u00a0el \u00a0anuncio \u00a0de la consecuencia \u00a0patrimonial \u00a0que \u00a0la \u00a0declaratoria \u00a0de \u00a0responsabilidad \u00a0acarrea respecto de los \u00a0bienes \u00a0involucrados \u00a0en \u00a0los delitos de cuya \u00a0comisi\u00f3n \u00a0se acusa al requerido, \u00a0tema \u00a0 ajeno \u00a0 a \u00a0 la \u00a0solicitud \u00a0de \u00a0extradici\u00f3n, \u00a0raz\u00f3n \u00a0 \u00a0por \u00a0 la \u00a0 cual \u00a0 no \u00a0 se \u00a0 encuentra \u00a0 \u00a0 \u00a0 comprendido \u00a0 \u00a0 \u00a0dentro \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0los aspectos \u00a0que \u00a0 deba \u00a0ocuparse \u00a0el \u00a0concepto a emitir \u00a0 \u00a0 \u00a0 por \u00a0 \u00a0 \u00a0la Sala. \u00a0\u00a0<\/p>\n<p>5. Equivalencia \u00a0de la providencia proferida en el extranjero \u00a0\u00a0<\/p>\n<p>Por \u00a0disposici\u00f3n \u00a0del \u00a0numeral \u00a02\u00b0 \u00a0del \u00a0art\u00edculo \u00a0493 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento Penal, Ley 906 de 2004, para que \u00a0pueda \u00a0ofrecerse \u00a0o \u00a0concederse \u00a0la \u00a0extradici\u00f3n, \u00a0es \u00a0necesario \u00a0que \u00a0el pa\u00eds \u00a0reclamante \u00a0haya \u00a0proferido \u00a0contra el requerido, resoluci\u00f3n de acusaci\u00f3n o su \u00a0equivalente. \u00a0\u00a0<\/p>\n<p>Tal exigencia se cumple tambi\u00e9n frente a \u00a0la \u00a0 solicitud \u00a0 de \u00a0 extradici\u00f3n \u00a0 del \u00a0 ciudadano \u00a0 colombiano \u00a0 JOS\u00c9 \u00a0 \u00a0DE \u00a0 JES\u00daS \u00a0 LE\u00d3N \u00a0 NI\u00d1O, \u00a0formalizada \u00a0por \u00a0el Gobierno de los Estados Unidos de Am\u00e9rica, toda vez que la \u00a0Acusaci\u00f3n \u00a0 \u00a0 No. \u00a008-CRIM \u00a01003, dictada el \u00a016 \u00a0 de \u00a0 octubre \u00a0 de \u00a02008, \u00a0en \u00a0la \u00a0Corte \u00a0Distrital de los Estados Unidos para el Distrito Sur de \u00a0Nueva \u00a0 \u00a0York, \u00a0 \u00a0es \u00a0equivalente \u00a0al \u00a0escrito \u00a0de \u00a0acusaci\u00f3n \u00a0establecido \u00a0en \u00a0el \u00a0art\u00edculo \u00a0337 del C\u00f3digo de Procedimiento \u00a0Penal, Ley 906 de 2004. \u00a0\u00a0<\/p>\n<p>En \u00a0 \u00a0efecto, \u00a0 \u00a0la \u00a0 \u00a0Acusaci\u00f3n \u00a0 \u00a0 No. \u00a0 \u00a0 08-CRIM \u00a0 \u00a0 \u00a0 \u00a01003, \u00a0contiene \u00a0entre \u00a0 otros \u00a0 aspectos, \u00a0 los \u00a0 atinentes \u00a0 a \u00a0la \u00a0individualizaci\u00f3n \u00a0concreta \u00a0del \u00a0acusado; \u00a0un relato resumido de las conductas \u00a0endilgadas \u00a0al requerido; describe las circunstancias de modo, tiempo y lugar en \u00a0que \u00a0fueron \u00a0ejecutadas; menciona las pruebas que le sirven de sustento; destaca \u00a0por \u00a0 qu\u00e9 \u00a0 tales \u00a0 hechos \u00a0 son \u00a0 jur\u00eddicamente \u00a0relevantes \u00a0al \u00a0realizar \u00a0la \u00a0calificaci\u00f3n \u00a0 \u00a0jur\u00eddica \u00a0 \u00a0con \u00a0 \u00a0las \u00a0 disposiciones \u00a0 penales \u00a0 sustantivas \u00a0transgredidas; \u00a0y \u00a0comporta \u00a0el \u00a0inicio \u00a0de \u00a0la \u00a0fase \u00a0del \u00a0juicio, \u00a0en donde el \u00a0procesado \u00a0tiene \u00a0la oportunidad de defenderse de los cargos a \u00e9l atribuidos, y \u00a0que culmina con la sentencia que pone fin al proceso. \u00a0\u00a0<\/p>\n<p>Como los anteriores elementos que contiene \u00a0la \u00a0 \u00a0Acusaci\u00f3n \u00a0 No. \u00a008-CRIM 1003, \u00a0tambi\u00e9n deben estar reunidos en el \u00a0escrito \u00a0de \u00a0acusaci\u00f3n \u00a0previsto \u00a0en \u00a0el \u00a0art\u00edculo \u00a0337 \u00a0del C\u00f3digo de Procedimiento Penal, Ley 906 de \u00a02004, se afirma la equivalencia entre las dos providencias. \u00a0\u00a0<\/p>\n<p>\u00a0 6. CONCLUSIONES \u00a0\u00a0<\/p>\n<p>Los \u00a0anteriores \u00a0razonamientos \u00a0permiten \u00a0establecer \u00a0 a \u00a0 la \u00a0Sala, \u00a0que de \u00a0acuerdo con lo manifestado por el \u00a0Ministerio \u00a0P\u00fablico, \u00a0est\u00e1n \u00a0dadas las exigencias \u00a0legales \u00a0para conceptuar de manera favorable respecto de los cargos referidos \u00a0 en \u00a0 la \u00a0 solicitud \u00a0de \u00a0extradici\u00f3n \u00a0del \u00a0ciudadano \u00a0colombiano \u00a0JOS\u00c9 \u00a0DE \u00a0JES\u00daS \u00a0 \u00a0 \u00a0LE\u00d3N \u00a0 \u00a0 \u00a0NI\u00d1O, \u00a0 \u00a0 \u00a0formalizada \u00a0 \u00a0 \u00a0 \u00a0por \u00a0 \u00a0 \u00a0 la \u00a0Embajada \u00a0de \u00a0Estados Unidos de Am\u00e9rica en nuestro \u00a0pa\u00eds. \u00a0\u00a0<\/p>\n<p>Por tanto, la \u00a0Corte \u00a0considera \u00a0pertinente \u00a0precisar \u00a0que, \u00a0en orden a garantizar los derechos \u00a0fundamentales \u00a0del \u00a0requerido, \u00a0si el Gobierno Nacional lo considera pertinente, \u00a0el \u00a0Estado requirente deber\u00e1 garantizar la permanencia en el pa\u00eds extranjero y \u00a0el \u00a0retorno \u00a0al \u00a0de \u00a0origen, en condiciones de dignidad y respeto por la persona \u00a0humana, \u00a0cuando el extraditado llegare a ser sobrese\u00eddo, absuelto, declarado no \u00a0culpable \u00a0o \u00a0eventos \u00a0similares, \u00a0incluso \u00a0despu\u00e9s \u00a0de su liberaci\u00f3n por haber \u00a0cumplido \u00a0la pena que le fuere impuesta en la sentencia de condena, en raz\u00f3n de \u00a0los \u00a0cargos \u00a0que \u00a0motivaron \u00a0la solicitud de extradici\u00f3n y por los cuales \u00e9sta \u00a0hubiere sido concedida. \u00a0\u00a0<\/p>\n<p>Del \u00a0 \u00a0mismo \u00a0 \u00a0modo, \u00a0 atendiendo \u00a0lo \u00a0dispuesto \u00a0en \u00a0el \u00a0art\u00edculo \u00a0494 \u00a0del C\u00f3digo de \u00a0Procedimiento \u00a0Penal, \u00a0Ley \u00a0906 \u00a0de 2004, se advertir\u00e1 que el Gobierno Nacional \u00a0puede \u00a0subordinar \u00a0la \u00a0concesi\u00f3n \u00a0de \u00a0la \u00a0extradici\u00f3n \u00a0a \u00a0las \u00a0condiciones que \u00a0considere \u00a0oportunas, \u00a0as\u00ed \u00a0como \u00a0exigir \u00a0que \u00a0el solicitado no sea juzgado por \u00a0hechos \u00a0anteriores \u00a0diversos \u00a0de los que motivaron la solicitud de extradici\u00f3n; \u00a0ni \u00a0sometido \u00a0a \u00a0sanciones \u00a0distintas \u00a0de \u00a0las que se le hubieren impuesto en la \u00a0eventual \u00a0condena; ni sometido a penas de muerte, destierro, prisi\u00f3n perpetua o \u00a0confiscaci\u00f3n; \u00a0ni \u00a0desaparici\u00f3n forzada, torturas, tratos crueles, inhumanos o \u00a0degradantes, \u00a0por \u00a0el pa\u00eds solicitante, de conformidad con lo dispuesto por los \u00a0art\u00edculos \u00a012 y 34 de la Constituci\u00f3n Pol\u00edtica de Colombia; y como lo sugiere \u00a0la \u00a0Procuradur\u00eda \u00a0General \u00a0de \u00a0la \u00a0Naci\u00f3n \u00a0a trav\u00e9s de su Delegada. \u00a0\u00a0<\/p>\n<p>As\u00ed \u00a0mismo, debe condicionar la entrega \u00a0de \u00a0 JOS\u00c9 \u00a0 DE \u00a0 JES\u00daS \u00a0LE\u00d3N \u00a0NI\u00d1O, \u00a0 \u00a0 \u00a0a \u00a0 \u00a0 \u00a0que \u00a0 \u00a0 \u00a0se \u00a0 \u00a0 \u00a0le \u00a0 \u00a0 \u00a0respeten \u00a0 \u00a0 \u00a0\u2013como a cualquier otro nacional en \u00a0las \u00a0mismas \u00a0condiciones- \u00a0todas \u00a0las \u00a0garant\u00edas \u00a0debidas \u00a0a \u00a0su \u00a0condici\u00f3n de \u00a0justiciable, \u00a0en \u00a0particular \u00a0a \u00a0que \u00a0tenga \u00a0acceso \u00a0a \u00a0un \u00a0proceso p\u00fablico sin \u00a0dilaciones \u00a0injustificadas, \u00a0a \u00a0que se presuma su inocencia, a que cuente con un \u00a0int\u00e9rprete, \u00a0a \u00a0que \u00a0tenga un defensor designado por \u00e9l o por el Estado, a que \u00a0se \u00a0le \u00a0conceda \u00a0el tiempo y los medios adecuados para que prepare la defensa, a \u00a0presentar \u00a0pruebas \u00a0y \u00a0controvertir \u00a0las \u00a0que \u00a0se \u00a0aduzcan \u00a0en \u00a0contra, a que su \u00a0situaci\u00f3n \u00a0de \u00a0privaci\u00f3n de la libertad se desarrolle en condiciones dignas, a \u00a0que \u00a0la \u00a0eventual \u00a0pena \u00a0que se le imponga no trascienda de su persona, a que la \u00a0sentencia \u00a0 pueda \u00a0ser \u00a0apelada \u00a0ante un tribunal superior, a que la pena privativa de la libertad tenga \u00a0la \u00a0finalidad \u00a0esencial \u00a0de \u00a0reforma y readaptaci\u00f3n social (Art\u00edculos 29 de la \u00a0Constituci\u00f3n; \u00a09 \u00a0y \u00a010 \u00a0de \u00a0la Declaraci\u00f3n Universal de los Derechos Humanos; \u00a05-3.6, \u00a07-2.5, 8-1.2 (a)(b)(c)(d)(e)(f)(g)(h).3.4.5, \u00a09 \u00a0de la Convenci\u00f3n Americana de Derechos Humanos; 9-2.3, 10-1.2.3, 14-1.2.3,5, \u00a0y 15 del Pacto Internacional de Derechos Civiles y Pol\u00edticos). \u00a0\u00a0<\/p>\n<p>Igualmente, el Gobierno debe condicionar \u00a0la \u00a0entrega a que el pa\u00eds solicitante, conforme a sus pol\u00edticas internas sobre \u00a0la \u00a0 materia, \u00a0 le \u00a0ofrezca \u00a0posibilidades \u00a0racionales \u00a0y \u00a0reales \u00a0para \u00a0que \u00a0el \u00a0extraditado \u00a0pueda \u00a0tener \u00a0contacto \u00a0regular \u00a0con \u00a0sus familiares m\u00e1s cercanos, \u00a0habida \u00a0cuenta \u00a0que \u00a0la Constituci\u00f3n de 1991, en su art\u00edculo 42, reconoce a la \u00a0familia \u00a0como \u00a0n\u00facleo \u00a0esencial \u00a0de \u00a0la \u00a0sociedad, \u00a0garantiza \u00a0su protecci\u00f3n y \u00a0reconoce \u00a0su honra, dignidad e intimidad, lo cual se refuerza con la protecci\u00f3n \u00a0adicional \u00a0que \u00a0a ese n\u00facleo le otorgan la Convenci\u00f3n Americana sobre Derechos \u00a0Humanos \u00a0 (art\u00edculo \u00a017) \u00a0y \u00a0el \u00a0Pacto \u00a0Internacional \u00a0de \u00a0Derechos \u00a0Civiles \u00a0y \u00a0Pol\u00edticos (art\u00edculo 23). \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, la Sala se\u00f1ala que en virtud de \u00a0lo \u00a0dispuesto \u00a0por \u00a0el \u00a0numeral \u00a02\u00ba \u00a0del \u00a0art\u00edculo \u00a0189 \u00a0de \u00a0la \u00a0Constituci\u00f3n \u00a0Pol\u00edtica, \u00a0corresponde \u00a0al \u00a0se\u00f1or \u00a0Presidente \u00a0de \u00a0la \u00a0Rep\u00fablica como supremo \u00a0director \u00a0de la pol\u00edtica exterior y de las relaciones internacionales, realizar \u00a0el \u00a0respectivo \u00a0seguimiento \u00a0a \u00a0los \u00a0condicionamientos \u00a0que \u00a0se \u00a0impongan \u00a0a \u00a0la \u00a0concesi\u00f3n \u00a0de la extradici\u00f3n y determinar las consecuencias que se derivar\u00edan \u00a0de su eventual incumplimiento. \u00a0\u00a0<\/p>\n<p>Cabe \u00a0 subrayar \u00a0 que \u00a0 JOS\u00c9 \u00a0DE \u00a0JES\u00daS \u00a0LE\u00d3N \u00a0NI\u00d1O, \u00a0se \u00a0encuentra \u00a0privado de la libertad para los efectos del tr\u00e1mite de extradici\u00f3n, \u00a0desde \u00a0 \u00a0 \u00a0el \u00a0 \u00a0 \u00a0veintid\u00f3s \u00a0 \u00a0 \u00a0(22) de \u00a0enero \u00a0de dos \u00a0 \u00a0mil \u00a0 \u00a0nueve \u00a0 (2009), lapso \u00a0que \u00a0se \u00a0tendr\u00e1 \u00a0como \u00a0parte \u00a0de \u00a0la \u00a0pena \u00a0que llegare a imponerse en el pa\u00eds \u00a0requirente. \u00a0\u00a0<\/p>\n<p>Por \u00a0lo \u00a0expuesto, \u00a0la Sala de Casaci\u00f3n \u00a0Penal \u00a0de \u00a0la \u00a0Corte Suprema de Justicia, CONCEPT\u00daA \u00a0FAVORABLEMENTE \u00a0a \u00a0la \u00a0extradici\u00f3n de JOS\u00c9 \u00a0DE \u00a0JES\u00daS \u00a0LE\u00d3N \u00a0NI\u00d1O, \u00a0de \u00a0anotaciones \u00a0conocidas \u00a0en el curso del proceso, por los cargos atribuidos en la \u00a0Acusaci\u00f3n \u00a0 \u00a0 No. \u00a008-CRIM \u00a01003, \u00a0dictada \u00a0el \u00a016 \u00a0de \u00a0octubre \u00a0de \u00a02008, \u00a0en la \u00a0Corte Distrital de los Estados Unidos para el Distrito Sur de \u00a0Nueva York. \u00a0\u00a0<\/p>\n<p>Devu\u00e9lvase \u00a0el expediente al Ministerio \u00a0del Interior y de Justicia para lo de su competencia. \u00a0\u00a0<\/p>\n<p>JULIO ENRIQUE SOCHA SALAMANCA \u00a0<\/p>\n<p>JOS\u00c9 \u00a0 \u00a0 \u00a0 LEONIDAS BUSTOS \u00a0MART\u00cdNEZ\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0SIGIFREDO ESPINOSA P\u00c9REZ \u00a0\u00a0<\/p>\n<p>ALFREDO G\u00d3MEZ QUINTERO\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0MAR\u00cdA DEL ROSARIO GONZ\u00c1LEZ DE LEMOS \u00a0\u00a0<\/p>\n<p>AUGUSTO \u00a0J. \u00a0IB\u00c1\u00d1EZ GUZM\u00c1N \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0JORGE LUIS QUINTERO MILAN\u00c9S\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0Excusa justificada \u00a0\u00a0<\/p>\n<p>YESID \u00a0RAM\u00cdREZ \u00a0BASTIDAS \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0JAVIER \u00a0ZAPATA ORTIZ \u00a0\u00a0<\/p>\n<p>TERESA RUIZ NU\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0 \u00a0<\/p>\n<p>1 \u00a0Conceptos \u00a0del \u00a03 \u00a0de \u00a0mayo de 2007 y 16 de diciembre de 2008, radicados 26756 y \u00a030626, respectivamente. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 31551 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 Magistrado Ponente: \u00a0 JAVIER ZAPATA ORTIZ \u00a0 Aprobado Acta No. \u00a0339 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Bogot\u00e1 \u00a0 D. \u00a0 C., \u00a0veintiocho \u00a0(28) \u00a0de \u00a0octubre de dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-18907","post","type-post","status-publish","format-standard","hentry","category-17"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/18907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=18907"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/18907\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=18907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=18907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=18907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}