{"id":12891,"date":"2023-09-08T21:04:27","date_gmt":"2023-09-08T21:04:27","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2563626-09-07\/"},"modified":"2023-09-08T21:04:27","modified_gmt":"2023-09-08T21:04:27","slug":"2563626-09-07","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2563626-09-07\/","title":{"rendered":"25636(26-09-07)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 25636 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>JAVIER ZAPATA ORTIZ \u00a0<\/p>\n<p>Aprobado \u00a0Acta \u00a0No. \u00a0181 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1, D.C., veintis\u00e9is (26) de septiembre \u00a0de dos mil siete (2007) \u00a0\u00a0<\/p>\n<p>DECISI\u00d3N \u00a0<\/p>\n<p>Con \u00a0el \u00a0fin \u00a0de \u00a0verificar \u00a0si \u00a0re\u00fane \u00a0los \u00a0requisitos \u00a0formales que condicionan su admisi\u00f3n, examina la Sala la demanda de \u00a0casaci\u00f3n \u00a0presentada \u00a0por \u00a0el \u00a0defensor \u00a0de FRANCISCO \u00a0JOS\u00c9 \u00a0VALIENTE \u00a0JIM\u00c9NEZ, \u00a0contra el fallo del 30 de \u00a0enero \u00a0de \u00a02006, mediante el cual el Tribunal Superior \u00a0Militar, \u00a0 \u00a0confirm\u00f3 \u00a0la \u00a0 sentencia \u00a0 expedida \u00a0 por \u00a0 el \u00a0 Juez \u00a0de Primera Instancia de la Fuerza Naval\u00a0 de Cartagena de \u00a0Indias, el\u00a0 13 de octubre de 2005. \u00a0\u00a0<\/p>\n<p>HECHOS Y ACTUACI\u00d3N PROCESAL \u00a0<\/p>\n<p>1. \u00a0Mediante orden \u00a0del \u00a0d\u00eda \u00a0n\u00famero \u00a0003 \u00a0del Comando Base Naval ARC Bolivar, entre el 9 al 13 de \u00a0enero \u00a0de \u00a02004, \u00a0fue \u00a0designado \u00a0para \u00a0prestar \u00a0servicio de guardia\u00a0 en la \u00a0Estaci\u00f3n \u00a0Naval \u00a0de \u00a0Tierra \u00a0Bomba, \u00a0el \u00a0S3AMS\u00a0 \u00a0FRANCISCO \u00a0JOS\u00c9 \u00a0VALIENTE \u00a0JIM\u00c9NEZ. Per\u00edodo dentro \u00a0del \u00a0cual \u00a0se ausent\u00f3 por una hora de las instalaciones referidas en un cami\u00f3n \u00a0C-30, \u00a0de \u00a0placa \u00a0militar \u00a04-4817, \u00a0que \u00a0se \u00a0encontraba \u00a0de \u00a0servicio, \u00a0llevando \u00a0materiales \u00a0que \u00a0hab\u00eda \u00a0adquirido; \u00a0desplaz\u00e1ndose \u00a0con tres infantes de marina \u00a0hasta \u00a0 Ca\u00f1o \u00a0 del \u00a0 Oro \u00a0e \u00a0informando \u00a0que \u00a0el \u00a0S\/A \u00a0estaba \u00a0enterado \u00a0de \u00a0su \u00a0actuar. \u00a0\u00a0<\/p>\n<p>2. La Fiscal\u00eda \u00a0 \u00a0 Sexta \u00a0 \u00a0 Penal \u00a0 \u00a0ante \u00a0 \u00a0el \u00a0 \u00a0Tribunal \u00a0 \u00a0Superior \u00a0Militar, \u00a0el \u00a022 \u00a0de \u00a0abril \u00a0de \u00a02005, \u00a0confirm\u00f3 \u00a0la \u00a0resoluci\u00f3n \u00a0de acusaci\u00f3n proferida por la Fiscal\u00eda de primera instancia el 28 \u00a0de \u00a0febrero \u00a0de \u00a02005, por los delitos de peculado por \u00a0uso \u00a0 y \u00a0 abandono \u00a0del \u00a0cargo, \u00a0contra \u00a0VALIENTE JIM\u00c9NEZ. \u00a0\u00a0<\/p>\n<p>El \u00a0Juzgado \u00a0de \u00a0Primera \u00a0 \u00a0Instancia \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 Fuerza \u00a0 Naval \u00a0 del \u00a0 Caribe, \u00a0 conden\u00f3 \u00a0al \u00a0suboficial \u00a0FRANCISCO JOS\u00c9 VALIENTE JIM\u00c9NEZ, como \u00a0autor \u00a0responsable de los punibles de peculado por uso \u00a0(art\u00edculo \u00a0 398 \u00a0 C\u00f3digo \u00a0Penal) \u00a0en \u00a0concurso \u00a0con \u00a0abandono \u00a0del \u00a0puesto \u00a0(art\u00edculo \u00a0124 \u00a0C\u00f3digo Penal \u00a0Militar), \u00a0a la pena principal de dieciocho (18) meses \u00a0de \u00a0prisi\u00f3n, \u00a0inhabilitaci\u00f3n \u00a0de \u00a0derechos \u00a0y \u00a0funciones p\u00fablicas por el mimo \u00a0lapso y la separaci\u00f3n absoluta de las Fuerzas Miliares. \u00a0\u00a0<\/p>\n<p>Contra la decisi\u00f3n del Juez interpuso\u00a0 \u00a0recurso \u00a0de \u00a0apelaci\u00f3n \u00a0la \u00a0defensa \u00a0t\u00e9cnica; alzada que fue resuelta mediante \u00a0sentencia \u00a0 \u00a0expedida \u00a0 \u00a0por \u00a0 \u00a0el \u00a0 \u00a0Tribunal \u00a0 \u00a0Militar, \u00a0 \u00a0al \u00a0 \u00a0confirmar \u00a0 la \u00a0 sentencia \u00a0 recurrida. \u00a0\u00a0<\/p>\n<p>El \u00a0defensor \u00a0de \u00a0FRANCISCO \u00a0 JOS\u00c9 \u00a0 VALIENTE \u00a0JIM\u00c9NEZ, \u00a0present\u00f3 \u00a0y \u00a0sustent\u00f3 el recurso de casaci\u00f3n. \u00a0\u00a0<\/p>\n<p>RESUMEN DE LA DEMANDA \u00a0<\/p>\n<p>Asegura el actor que no existe prueba de la \u00a0existencia \u00a0de \u00a0los \u00a0delitos, \u00a0que \u00a0los \u00a0infantes \u00a0no \u00a0ostentan \u00a0la \u00a0calidad \u00a0de \u00a0investigadores \u00a0por \u00a0ello \u00a0la operaci\u00f3n fue arbitraria e inexistente; que en el \u00a0plenario \u00a0no \u00a0existe certificado de representaci\u00f3n legal de la firma Proasercon \u00a0Ltda., \u00a0que la comunidad militar pretermiti\u00f3 la conducta de su prohijado porque \u00a0no cumplieron con las consignas de la guardia. \u00a0\u00a0<\/p>\n<p>Por \u00a0tanto, \u00a0invoc\u00f3 la causal \u201cprimera \u00a0 \u00a0de \u00a0 \u00a0excepcionalidad \u00a0 de \u00a0 casaci\u00f3n\u201d \u00a0del \u00a0art\u00edculo \u00a0368 \u00a0del \u00a0C\u00f3digo \u00a0Penal \u00a0Militar; \u00a0alegando \u00a0que \u00a0\u201cla sentencia fue confirmada sin tener en cuenta el \u00a0principio \u00a0de \u00a0razonabilidad \u00a0que en forma reiterada a dictado la corte y que ha \u00a0servido \u00a0 de \u00a0 ense\u00f1anza \u00a0 en \u00a0 el \u00a0 caso \u00a0del\u00a0 \u00a0delito \u00a0de \u00a0peculado \u00a0por \u00a0uso\u201d \u00a0\u00a0<\/p>\n<p>Para \u00a0 constatar \u00a0sus \u00a0planeamientos, \u00a0el \u00a0libelista \u00a0trae \u00a0a \u00a0colaci\u00f3n \u00a0los \u00a0elementos \u00a0del \u00a0peculado \u00a0por uso, habla del \u00a0servidor \u00a0p\u00fablico, \u00a0informa que el veh\u00edculo se lo entregaron para una peque\u00f1a \u00a0reparaci\u00f3n, \u00a0que \u00a0\u00e9l no era el encargado de custodiar o administrar el cami\u00f3n \u00a0y \u00a0que \u00a0no \u00a0ten\u00eda \u00a0esas \u00a0funciones. \u00a0Que \u00a0el \u00a0uso de tal veh\u00edculo en el que se \u00a0transportaron \u00a0materiales \u00a0no sabe a qu\u00e9 persona pertenece, que su representado \u00a0s\u00f3lo \u00a0utiliz\u00f3 \u00a0cuarenta \u00a0minutos \u00a0del \u00a0referido automotor, es decir, -agreg\u00f3- \u00a0\u201cle \u00a0dio un uso razonable de corto tiempo, frente a \u00a0esas \u00a0consideraciones \u00a0la \u00a0jurisprudencia \u00a0de \u00a0la \u00a0corte \u00a0se \u00a0ha \u00a0pronunciado al \u00a0expresar \u00a0que \u00a0no \u00a0existe \u00a0dicho \u00a0delito \u00a0cuando \u00a0el uso que se le da al bien de \u00a0estado es razonable\u2026 con base al principio de razonabilidad\u201d. \u00a0\u00a0<\/p>\n<p>Por ello los funcionarios del Estado le dan \u00a0un \u00a0uso \u00a0razonable \u00a0a los abonados telef\u00f3nicos, entre otros bienes; entendiendo \u00a0el \u00a0libelista que el Tribunal conden\u00f3 a su prohijado porque trasport\u00f3 material \u00a0de \u00a0construcci\u00f3n \u00a0ajeno, \u00a0conducta \u00a0t\u00edpica \u00a0diferente \u00a0al \u00a0peculado \u00a0por \u00a0uso. \u00a0\u00a0<\/p>\n<p>Tampoco \u00a0existe \u00a0delito \u00a0de \u00a0abandono \u00a0del \u00a0puesto, \u00a0 \u00a0teniendo \u00a0 \u00a0en \u00a0 \u00a0cuenta \u00a0 que \u00a0 VALIENTE \u00a0JIM\u00c9NEZ \u00a0era \u00a0motorista \u00a0para \u00a0el mantenimiento y la \u00a0reparaci\u00f3n \u00a0de \u00a0veh\u00edculos, \u00a0m\u00e1s \u00a0no \u00a0guardia\u00a0 \u00a0armada: \u00a0ingrediente \u00a0que \u00a0requiere la norma que para consumar tal il\u00edcito. \u00a0\u00a0<\/p>\n<p>Sostiene \u00a0que \u00a0invoca \u00a0la causal segunda de \u00a0casaci\u00f3n \u00a0contenida \u00a0en \u00a0el \u00a0\u201cart\u00edculo \u00a029 \u00a0de la \u00a0constituci\u00f3n \u00a0pol\u00edtica\u2026 \u00a0cuando \u00a0la \u00a0sentencia \u00a0se \u00a0ha \u00a0dictado en un juicio \u00a0desconociendo el principio de debido proceso. \u00a0\u00a0<\/p>\n<p>Puntualiza \u00a0 \u00a0que \u00a0 se \u00a0 pretermitieron \u00a0formalidades \u00a0procesales, \u00a0que las pruebas que se recogen en la actuaci\u00f3n penal \u00a0tienen \u00a0un \u00a0fundamento de \u201cprobalidad\u201d \u00a0como \u00a0una posibilidad que se haya infringido la ley; entonces esa \u00a0probalidad \u00a0al \u00a0demostrar \u00a0o \u00a0no \u00a0la existencia de los delitos vulnera el debido \u00a0proceso \u00a0al \u00a0no \u00a0haberse \u00a0decretado \u00a0las \u00a0pruebas \u00a0pedidas por la defensa, al no \u00a0poderse \u00a0controvertir \u00a0las que aparecen contra el sentenciado. Por tanto, \u201c\u2026 \u00a0sin \u00a0pruebas \u00a0el \u00a0sindicado \u00a0no \u00a0tiene \u00a0\u00e9xito\u2026 \u00a0la \u00a0certeza \u00a0 viene \u00a0 siendo \u00a0 la \u00a0 persuasi\u00f3n \u00a0 de \u00a0 la \u00a0 verdad\u2026\u201d \u00a0como \u00a0le negaron las pruebas le prohibieron conocer la certeza de \u00a0los hechos. \u00a0\u00a0<\/p>\n<p>Concluye \u00a0 el \u00a0 actor \u00a0 que \u00a0\u201cfrente \u00a0 \u00a0a \u00a0 \u00a0las \u00a0 \u00a0anteriores \u00a0 razones \u00a0 y \u00a0 consideraciones \u00a0jur\u00eddicas\u201d \u00a0se \u00a0case \u00a0a \u00a0favor \u00a0de su prohijado el \u00a0fallo. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE \u00a0LA \u00a0SALA \u00a0\u00a0<\/p>\n<p>La censura presentada a favor de \u00a0FRANCISCO \u00a0JOS\u00c9 \u00a0VALIENTE JIM\u00c9NEZ, no \u00a0re\u00fane \u00a0 los \u00a0 m\u00ednimos \u00a0 presupuestos \u00a0de \u00a0coherencia \u00a0y \u00a0l\u00f3gica-argumentativa \u00a0puntualizados \u00a0por la jurisprudencia para admitir la demanda. Propone como punto \u00a0de \u00a0partida \u00a0para \u00a0lograr \u00a0la \u00a0infirmaci\u00f3n \u00a0del fallo de segundo nivel, la v\u00eda \u00a0excepcional, \u00a0fundamentada en las normas contenidas en el C\u00f3digo Penal Militar, \u00a0por \u00a0violaci\u00f3n del principio de razonabilidad; en su desarrollo, presentaci\u00f3n, \u00a0argumentaci\u00f3n \u00a0y \u00a0demostraci\u00f3n \u00a0incurre en graves fallas que atentan contra la \u00a0filosof\u00eda que inspira el recurso extraordinario. \u00a0\u00a0<\/p>\n<p>No es un escrito de libre confecci\u00f3n con el \u00a0que \u00a0se pretenda derrumbar la doble presunci\u00f3n de acierto y legalidad que viene \u00a0unida \u00a0los \u00a0fallos, \u00a0tampoco \u00a0es \u00a0una \u00a0adici\u00f3n \u00a0de \u00a0una \u00a0multiplicidad de ideas \u00a0hipot\u00e9ticas \u00a0en \u00a0b\u00fascaqueda \u00a0de \u00a0un \u00a0fin \u00a0jur\u00eddico subjetivo para asegurar la \u00a0demostraci\u00f3n \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0causal \u00a0 alegada.\u00a0 \u00a0\u00a0<\/p>\n<p>La \u00a0censura \u00a0se \u00a0sustent\u00f3 \u00a0en \u00a0afirmaciones \u00a0confusas, \u00a0 enmara\u00f1adas \u00a0 e \u00a0 insustanciales, \u00a0 por \u00a0 las \u00a0siguientes \u00a0razones: \u00a0\u00a0<\/p>\n<p>Primera: \u00a0 se \u00a0justifica \u00a0 la \u00a0 casaci\u00f3n \u00a0discrecional \u00a0en \u00a0la \u00a0medida que se debe fundamentar su ataque con el objeto de \u00a0demostrarle \u00a0a \u00a0la \u00a0Sala, \u00a0uno \u00a0de \u00a0los \u00a0siguientes \u00a0motivos, \u00a0para acceder a su \u00a0estudio: \u00a0 1) \u00a0buscar \u00a0el \u00a0restablecimiento \u00a0de \u00a0una \u00a0garant\u00eda de derecho fundamental, que en criterio del \u00a0libelista,\u00a0 \u00a0 fue \u00a0 trasgredida \u00a0 por \u00a0 los \u00a0 falladores, \u00a0 y \u00a02) \u00a0 perseguir \u00a0 el \u00a0 desarrollo \u00a0de \u00a0la \u00a0jurisprudencia. \u00a0\u00a0<\/p>\n<p>Exigencia \u00a0que \u00a0prev\u00e9 confeccionar en forma \u00a0clara, \u00a0precisa \u00a0y consecuente con el historial procesal, uno de los dos motivos \u00a0seleccionados \u00a0o \u00a0ambos si se presenta el caso, a fin de\u00a0 argumentar el por \u00a0qu\u00e9 \u00a0la \u00a0Sala\u00a0 \u00a0debe \u00a0intervenir \u00a0en \u00a0un asunto en el que no concurren los \u00a0presupuestos b\u00e1sicos para la casaci\u00f3n ordinaria.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Si \u00a0la \u00a0casaci\u00f3n \u00a0discrecional \u00a0busca \u00a0un \u00a0pronunciamiento para aclarar \u00a0situaciones \u00a0jur\u00eddicas \u00a0confusas, oscuras e ininteligibles es indispensable que \u00a0se \u00a0centre \u00a0la propuesta discrecional en i) \u00a0la unificaci\u00f3n hermen\u00e9utica de criterios contrapuestos sobre un \u00a0mismo \u00a0 \u00a0tema, \u00a0 ii) \u00a0 la \u00a0actualizaci\u00f3n \u00a0 de \u00a0 la \u00a0 doctrina, \u00a0iii) \u00a0o \u00a0el desarrollo de una nueva concepci\u00f3n normativa; con un doble \u00a0prop\u00f3sito: \u00a0primero, \u00a0argumentar \u00a0la \u00a0necesidad \u00a0y \u00a0utilidad \u00a0de \u00a0la \u00a0soluci\u00f3n \u00a0propuesta \u00a0y, \u00a0segundo, \u00a0de qu\u00e9 manera podr\u00eda servir de par\u00e1metro rector a la \u00a0actividad judicial.\u00a0 \u00a0\u00a0<\/p>\n<p>Pero \u00a0ah\u00ed \u00a0no cesa el ejercicio intelectual \u00a0del \u00a0 \u00a0 demandante, \u00a0 \u00a0 es \u00a0 \u00a0 imperativo, \u00a0 \u00a0en \u00a0 \u00a0consecuencia \u00a0 \u00a0\u2013una \u00a0 \u00a0vez \u00a0 \u00a0superados\u00a0 \u00a0 los \u00a0presupuestos \u00a0anteriores- \u00a0desarrollar cada cargo como si fuese una casaci\u00f3n \u00a0com\u00fan, \u00a0es \u00a0decir, \u00a0con \u00a0las \u00a0exigencias \u00a0l\u00f3gico-jur\u00eddicas \u00a0que \u00a0imponen \u00a0una \u00a0adecuada censura, la que debe \u00a0condensar los errores de juicio o de actividad. \u00a0\u00a0<\/p>\n<p>Segunda: \u00a0auspiciando \u00a0una \u00a0misi\u00f3n \u00a0pedag\u00f3gica \u00a0la Sala precisar\u00e1 algunas falencias del \u00a0libelo, \u00a0indicando \u00a0-en \u00a0principio- \u00a0que el postulado de autonom\u00eda de casaci\u00f3n \u00a0fue \u00a0desconocido \u00a0en \u00a0su \u00a0integridad, \u00a0al \u00a0mezclar \u00a0unas causales con otras, por \u00a0ejemplo, \u00a0 \u00a0anunci\u00f3 \u00a0 \u00a0que \u00a0 el \u00a0 \u201cprincipio \u00a0 de \u00a0razonabilidad\u201d \u00a0en el delito de peculado por uso es \u00a0el \u00a0que \u00a0se \u00a0debe \u00a0aplicar, \u00a0aduciendo el actor para complementar la motivaci\u00f3n \u00a0violaciones \u00a0al \u00a0debido \u00a0proceso, \u00a0al \u00a0principio de investigaci\u00f3n integral y al \u00a0contradictorio. \u00a0\u00a0<\/p>\n<p>Tercera: el ataque \u00a0lo \u00a0estaba \u00a0realizando por v\u00eda directa, al discriminar los elementos normativos \u00a0del \u00a0tipo \u00a0penal \u00a0de peculado por uso, no obstante, termina valorando los medios \u00a0probatorios \u00a0en \u00a0conexi\u00f3n \u00a0a \u00a0su propio criterio, reorganizando, inclusive, los \u00a0hechos \u00a0a \u00a0su \u00a0acomodo; cuesti\u00f3n, desde luego, prohibida en casaci\u00f3n, toda vez \u00a0que \u00a0el recurso no es una nueva e ilimitada instancia donde se puede extender el \u00a0discurso a limites insustanciales.\u00a0 \u00a0\u00a0<\/p>\n<p>Cuarta: tal es su \u00a0confusi\u00f3n, \u00a0que \u00a0remata \u00a0el \u00a0cargo afirmando que se vulner\u00f3 el debido proceso, \u00a0sin \u00a0que \u00a0hubiese \u00a0realizado \u00a0alg\u00fan \u00a0ejercicio \u00a0jur\u00eddico \u00a0e \u00a0intelectual \u00a0para \u00a0demostrarlo, s\u00f3lo se qued\u00f3 con el enunciado.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Quinta: el actor en \u00a0esencia \u00a0afirm\u00f3 que no hab\u00eda prueba para condenar y que no logr\u00f3 controvertir \u00a0las \u00a0pruebas \u00a0incriminatorias, \u00a0con lo cual, se inmiscuye en una combinaci\u00f3n de \u00a0teor\u00edas, \u00a0causales \u00a0y \u00a0cargos que se excluyen entre s\u00ed, al no haber sido\u00a0 \u00a0sustentados \u00a0en cap\u00edtulos diversos, todo lo cual, bajo el imperio del principio \u00a0de \u00a0limitaci\u00f3n, \u00a0la \u00a0Sala \u00a0no \u00a0puede \u00a0entrar \u00a0a \u00a0subsanar \u00a0ese \u00a0manojo de ideas \u00a0deshilvanadas \u00a0 para \u00a0 resolver \u00a0 de \u00a0 fondo, \u00a0 porque \u00a0 el \u00a0 desatino \u00a0 en \u00a0 la \u00a0l\u00f3gica-argumentativa es abrumador. \u00a0\u00a0<\/p>\n<p>Sexta: por \u00faltimo, \u00a0el \u00a0 \u00a0 principio \u00a0 \u00a0de \u00a0 \u00a0trascendencia \u00a0fue olvidado por el demandante, el cual es vital a fin de derruir \u00a0los yerros conculcados en instancias. \u00a0\u00a0<\/p>\n<p>Se \u00a0verifica, \u00a0entonces, \u00a0que \u00a0el \u00a0libelista \u00a0presenta \u00a0una \u00a0alegaci\u00f3n \u00a0producto \u00a0de \u00a0su \u00a0propia percepci\u00f3n del derecho, los \u00a0hechos \u00a0y \u00a0las \u00a0pruebas \u00a0contra \u00a0lo \u00a0afirmado por el Juez Colegiado, sin ninguna \u00a0prevalencia \u00a0en la l\u00f3gica-jur\u00eddica requerida para sustentar la demanda, con lo \u00a0cual \u00a0todas sus pretensiones se alejan de la filosof\u00eda que inspira el instituto \u00a0casacional. \u00a0\u00a0<\/p>\n<p>La \u00a0 sumatoria \u00a0de \u00a0defectos \u00a0sustanciales \u00a0enunciados \u00a0 atr\u00e1s \u00a0no \u00a0le \u00a0dejan \u00a0otro \u00a0camino \u00a0a \u00a0la \u00a0Sala \u00a0que \u00a0inadmitir \u00a0 la \u00a0 demanda \u00a0de \u00a0casaci\u00f3n, \u00a0presentada \u00a0 a \u00a0favor \u00a0de \u00a0FRANCISCO \u00a0JOS\u00c9 \u00a0VALIENTE \u00a0JIM\u00c9NEZ, \u00a0de \u00a0conformidad \u00a0con \u00a0lo preceptuado en el \u00a0art\u00edculo \u00a0213 \u00a0de la Ley 600 de 2000; sin olvidar que, estudiado el proceso, no \u00a0se \u00a0 percibe \u00a0en \u00a0su \u00a0contexto, \u00a0que \u00a0se \u00a0hubiese \u00a0violentado \u00a0alguna \u00a0garant\u00eda \u00a0fundamental \u00a0que \u00a0amerite \u00a0el facultativo ejercicio de la oficiosidad, en virtud \u00a0de \u00a0 los \u00a0 dispuesto \u00a0 en \u00a0el \u00a0art\u00edculo \u00a0216 \u00a0de \u00a0la \u00a0misma \u00a0obra \u00a0instrumental \u00a0citada. \u00a0\u00a0<\/p>\n<p>Con \u00a0 fundamento \u00a0 en \u00a0 lo \u00a0expuesto, \u00a0la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n \u00a0Penal \u00a0de \u00a0la \u00a0Corte \u00a0Suprema de \u00a0Justicia, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0\u00a0<\/p>\n<p>Primero: \u00a0INADMITIR \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0a \u00a0nombre \u00a0de \u00a0FRANCISCO JOS\u00c9 \u00a0VALIENTE \u00a0 \u00a0 JIM\u00c9NEZ. \u00a0\u00a0<\/p>\n<p>Segundo: \u00a0Contra \u00a0la \u00a0presente \u00a0providencia \u00a0no procede recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0C\u00f3piese, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 comun\u00edquese, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0c\u00famplase. \u00a0\u00a0<\/p>\n<p>ALFREDO \u00a0 \u00a0G\u00d3MEZ \u00a0QUINTERO \u00a0\u00a0<\/p>\n<p>Cita medica \u00a0<\/p>\n<p>SIGIFREDO \u00a0 ESPINOSA \u00a0 P\u00c9REZ \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0MAR\u00cdA DEL \u00a0ROSARIO \u00a0GONZ\u00c1LEZ \u00a0DE \u00a0LEMOS \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>AUGUSTO \u00a0J. \u00a0IBA\u00d1EZ \u00a0GUZM\u00c1N \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0JORGE LUIS \u00a0QUINTERO \u00a0 \u00a0MILAN\u00c9S \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>YESID \u00a0 RAM\u00cdREZ \u00a0 BASTIDAS \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0JULIO \u00a0 \u00a0ENRIQUE \u00a0 \u00a0SOCHA \u00a0SALAMANCA \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>MAURO \u00a0 \u00a0SOLARTE \u00a0PORTILLA \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0JAVIER ZAPATA \u00a0ORTIZ \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Secretaria \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 25636 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado Ponente \u00a0 JAVIER ZAPATA ORTIZ \u00a0 Aprobado \u00a0Acta \u00a0No. \u00a0181 \u00a0\u00a0 Bogot\u00e1, D.C., veintis\u00e9is (26) de septiembre \u00a0de dos mil siete (2007) \u00a0\u00a0 DECISI\u00d3N \u00a0 Con \u00a0el \u00a0fin \u00a0de \u00a0verificar \u00a0si \u00a0re\u00fane \u00a0los \u00a0requisitos \u00a0formales que condicionan su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-12891","post","type-post","status-publish","format-standard","hentry","category-15"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/12891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=12891"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/12891\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=12891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=12891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=12891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}