{"id":11492,"date":"2023-09-08T19:54:01","date_gmt":"2023-09-08T19:54:01","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2511916-06-06\/"},"modified":"2023-09-08T19:54:01","modified_gmt":"2023-09-08T19:54:01","slug":"2511916-06-06","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2511916-06-06\/","title":{"rendered":"25119(16-06-06)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 25119 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA \u00a0 DE \u00a0 CASACI\u00d3N \u00a0PENAL \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0Magistrado \u00a0Ponente \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Dr. EDGAR LOMBANA TRUJILLO \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Aprobado Acta No. 057 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1 \u00a0D. C., diecis\u00e9is (16) de junio de \u00a0dos mil seis (2006). \u00a0\u00a0<\/p>\n<p>VISTOS \u00a0<\/p>\n<p>Con \u00a0el \u00a0fin \u00a0de \u00a0verificar \u00a0si \u00a0re\u00fane los \u00a0requisitos \u00a0formales que condicionan su admisi\u00f3n, examina la Sala la demanda de \u00a0casaci\u00f3n \u00a0presentada \u00a0por el defensor de MAR\u00cdA LUCILA ACOSTA ARENAS, contra el \u00a0fallo \u00a0del \u00a010 \u00a0de \u00a0octubre \u00a0de \u00a02005, \u00a0mediante el cual el Tribunal Superior de \u00a0Pereira \u00a0confirm\u00f3 la sentencia dictada el 5 de septiembre del mismo a\u00f1o por el \u00a0Juzgado \u00a0Tercero \u00a0Penal \u00a0del Circuito de Pereira, que conden\u00f3 a dicha procesada \u00a0como \u00a0autora \u00a0de \u00a0\u201cTr\u00e1fico, fabricaci\u00f3n o porte de \u00a0estupefacientes, \u00a0 en \u00a0 la \u00a0 modalidad \u00a0 de \u00a0 llevar \u00a0 consigo \u00a0 250 \u00a0gramos \u00a0de \u00a0coca\u00edna\u201d, \u00a0a \u00a0la \u00a0pena principal de noventa y seis \u00a0(96) \u00a0meses de prisi\u00f3n, a inhabilitaci\u00f3n de derechos y funciones p\u00fablicas por \u00a0igual \u00a0lapso, \u00a0al pago de multa por valor de $ 50.800.000; le neg\u00f3 el subrogado \u00a0de \u00a0la \u00a0suspensi\u00f3n \u00a0condicional \u00a0de la ejecuci\u00f3n de la pena; y le concedi\u00f3 la \u00a0prisi\u00f3n domiciliaria. \u00a0\u00a0<\/p>\n<p>HECHOS Y ACTUACI\u00d3N RELEVANTE \u00a0<\/p>\n<p>1. \u00a0Los \u00a0acontecimientos \u00a0que originaron la \u00a0investigaci\u00f3n \u00a0penal \u00a0fueron \u00a0relatados \u00a0de \u00a0la siguiente manera por la Sala de \u00a0Decisi\u00f3n \u00a0Penal \u00a0del \u00a0Tribunal \u00a0Superior de Pereira, en la sentencia de segunda \u00a0instancia del 10 de octubre de 2005: \u00a0\u00a0<\/p>\n<p>\u201cLos hechos tuvieron ocurrencia el 22 de \u00a0abril \u00a0pasado, \u00a0cuando \u00a0la se\u00f1ora Acosta Arenas se dispon\u00eda a salir del pa\u00eds, \u00a0acompa\u00f1ada \u00a0de \u00a0un \u00a0menor, para Espa\u00f1a. Al momento de pasar por la secci\u00f3n de \u00a0emigraci\u00f3n \u00a0del \u00a0aeropuerto Mateca\u00f1a de esta capital, y los polic\u00edas hacer la \u00a0pesquisa \u00a0de \u00a0rutina, encontraron una bolsa, en el interior de la cual hab\u00eda un \u00a0sobre \u00a0de \u00a0manila \u00a0que conten\u00eda una agenda, la que result\u00f3 sospechosa para los \u00a0gendarmes, \u00a0por \u00a0lo \u00a0que le insertaron un \u201cchuzo\u201d y notaron que en las tapas \u00a0hab\u00eda \u00a0una sustancia pulverulenta, amarillenta, por lo que procedieron a llamar \u00a0a \u00a0los \u00a0servidores \u00a0p\u00fablicos \u00a0encargados \u00a0de \u00a0realizar \u00a0la \u00a0verificaci\u00f3n de la \u00a0sustancia, \u00a0quienes \u00a0obtuvieron \u00a0resultado \u00a0positivo \u00a0para coca\u00edna, en cantidad \u00a0neta de 250 gramos.\u201d \u00a0\u00a0<\/p>\n<p>2. \u00a0Legalizada \u00a0la \u00a0captura \u00a0por el Juez de \u00a0Control \u00a0de \u00a0Garant\u00edas, \u00a0en\u00a0 \u00a0audiencia preliminar llevada a cabo el 22 de \u00a0abril \u00a0de \u00a02005,\u00a0 \u00a0la \u00a0Fiscal\u00eda \u00a0que \u00a0asumi\u00f3 \u00a0el \u00a0conocimiento del asunto \u00a0imput\u00f3 \u00a0a \u00a0la \u00a0se\u00f1ora MAR\u00cdA LUCILA ACOSTA ARENAS el delito de \u201ctr\u00e1fico, \u00a0 fabricaci\u00f3n \u00a0o \u00a0porte \u00a0de \u00a0estupefacientes\u201d, \u00a0tipificado \u00a0en \u00a0el art\u00edculo 376, inciso tercero, del C\u00f3digo \u00a0Penal, \u00a0Ley \u00a0599 \u00a0de \u00a02000, \u00a0aclarando que \u201cel verbo \u00a0rector \u00a0ser\u00e1 el de tr\u00e1fico, a t\u00edtulo de autor.\u201d1; \u00a0 \u00a0 \u00a0 \u00a0 atribuci\u00f3n \u00a0 \u00a0que \u00a0 la \u00a0 implicada \u00a0 no \u00a0 acept\u00f3; \u00a0 y \u00a0por \u00a0el cual le fue impuesta la medida \u00a0de aseguramiento de detenci\u00f3n preventiva en su domicilio. \u00a0\u00a0<\/p>\n<p>3. \u00a0El \u00a019 \u00a0de \u00a0mayo \u00a0de \u00a02005 la Fiscal\u00eda \u00a0Veintiuno \u00a0Seccional \u00a0de \u00a0Pereira \u00a0alleg\u00f3 \u00a0el \u00a0escrito \u00a0de \u00a0acusaci\u00f3n, \u00a0con la \u00a0siguiente \u00a0 adecuaci\u00f3n \u00a0 t\u00edpica: \u00a0\u201cel \u00a0delito \u00a0de \u00a0fabricaci\u00f3n, \u00a0tr\u00e1fico \u00a0y \u00a0porte de estupefacientes, consagrado en el art\u00edculo \u00a0376 \u00a0del \u00a0C.P. \u00a0inciso tercero; modificado por el art. 14 de la Ley 890 de 2004, \u00a0en la modalidad de PORTE DE ESTUPEFACIENTES\u201d. \u00a0\u00a0<\/p>\n<p>4. \u00a0El \u00a0asunto \u00a0correspondi\u00f3 \u00a0al \u00a0Juzgado \u00a0Tercero \u00a0Penal \u00a0del \u00a0circuito \u00a0de Pereira, autoridad que convoc\u00f3 a audiencia de \u00a0formulaci\u00f3n \u00a0de \u00a0la \u00a0acusaci\u00f3n, \u00a0llevada \u00a0a cabo el 8 de julio de 2005, en los \u00a0t\u00e9rminos \u00a0del \u00a0art\u00edculo \u00a0339 \u00a0del \u00a0C\u00f3digo \u00a0de Procedimiento Penal, Ley 906 de \u00a02004. \u00a0\u00a0<\/p>\n<p>La \u00a0Fiscal\u00eda \u00a0ley\u00f3 la imputaci\u00f3n como la \u00a0hab\u00eda \u00a0plasmado \u00a0en \u00a0el \u00a0escrito \u00a0acusatorio, \u00a0quedando, \u00a0entonces \u00a0acusada \u00a0la \u00a0implicada \u00a0 MAR\u00cdA \u00a0 LUCILA \u00a0 ACOSTA \u00a0 ARENAS \u00a0 por \u00a0 el \u00a0delito \u00a0de \u00a0fabricaci\u00f3n, \u00a0tr\u00e1fico \u00a0y \u00a0porte \u00a0de estupefacientes, \u00a0 \u00a0 \u201cen \u00a0 \u00a0 la \u00a0 \u00a0modalidad \u00a0 \u00a0de \u00a0porte\u201d. \u00a0\u00a0<\/p>\n<p>5. \u00a0 Se \u00a0desarrollo \u00a0el \u00a0juicio \u00a0oral \u00a0en \u00a0circunstancias \u00a0normales, \u00a0y \u00a0finalizado \u00a0el \u00a0debate, \u00a0con \u00a0sentencia \u00a0del \u00a05 de \u00a0septiembre \u00a0de \u00a02005, el Juzgado S\u00e9ptimo Penal del Circuito de Pereira conden\u00f3 \u00a0a \u00a0 \u00a0MAR\u00cdA \u00a0 \u00a0LUCILA \u00a0 \u00a0ACOSTA \u00a0 \u00a0ARENAS \u00a0 \u00a0como \u00a0 \u00a0autora \u00a0 \u00a0de \u00a0 \u201cTr\u00e1fico, \u00a0 fabricaci\u00f3n \u00a0o \u00a0porte \u00a0de \u00a0estupefacientes, \u00a0en \u00a0la \u00a0modalidad \u00a0 \u00a0de \u00a0 llevar \u00a0 consigo \u00a0 250 \u00a0 gramos \u00a0 de \u00a0 coca\u00edna\u201d, \u00a0a \u00a0la pena principal de noventa y seis (96) meses de prisi\u00f3n, y \u00a0adopt\u00f3 las otras determinaciones rese\u00f1adas en la parte inicial. \u00a0\u00a0<\/p>\n<p>6. El defensor de la procesada interpuso el \u00a0recurso \u00a0de \u00a0apelaci\u00f3n; \u00a0y \u00a0al\u00a0 \u00a0desatar \u00a0la \u00a0alzada, \u00a0con fallo del 10 de \u00a0octubre \u00a0de \u00a02005, \u00a0una Sala de Decisi\u00f3n Penal del Tribunal Superior de Pereira \u00a0confirm\u00f3 \u00edntegramente la sentencia de primera instancia. \u00a0\u00a0<\/p>\n<p>7. \u00a0 Inconforme \u00a0 con \u00a0la \u00a0determinaci\u00f3n \u00a0anterior, \u00a0el \u00a0defensor \u00a0de \u00a0MAR\u00cdA \u00a0LUCILA \u00a0ACOSTA \u00a0ARENAS interpuso el recurso \u00a0extraordinario de casaci\u00f3n, cuya admisibilidad se analiza. \u00a0\u00a0<\/p>\n<p>LA \u00a0 DEMANDA \u00a0 DE \u00a0CASACI\u00d3N \u00a0\u00a0<\/p>\n<p>Dos \u00a0cargos \u00a0postula \u00a0el defensor de MAR\u00cdA \u00a0LUCILA \u00a0ACOSTA \u00a0ARENAS \u00a0contra \u00a0el \u00a0fallo del Tribunal Superior de Pereira. Uno, \u00a0invocando \u00a0la \u00a0causal \u00a0segunda \u00a0de \u00a0casaci\u00f3n \u00a0prevista \u00a0en el art\u00edculo 181 del \u00a0C\u00f3digo \u00a0de Procedimiento Penal, Ley 906 de 2004, por desconocimiento del debido \u00a0proceso; \u00a0y \u00a0el otro, con base en la causal tercera ib\u00eddem, por desconocimiento \u00a0de las reglas de apreciaci\u00f3n de las pruebas. \u00a0\u00a0<\/p>\n<p>PRIMER \u00a0CARGO: \u00a0Nulidad por desconocimiento \u00a0del debido proceso \u00a0\u00a0<\/p>\n<p>Asegura \u00a0el \u00a0libelista \u00a0que \u00a0el \u00a0fallo \u00a0es \u00a0incongruente \u00a0respecto \u00a0de los cargos endilgados en la audiencia de formulaci\u00f3n \u00a0de \u00a0la acusaci\u00f3n, pues en \u00e9sta se llam\u00f3 ajuicio a MARTHA LUCILA ACOSTA ARENAS \u00a0por \u00a0 \u00a0\u201cporte \u00a0 \u00a0de \u00a0 estupefacientes\u201d; \u00a0en \u00a0la \u00a0sentencia \u00a0de \u00a0primera \u00a0instancia \u00a0fue \u00a0condenada por \u00a0\u201cllevar \u00a0 \u00a0consigo\u201d \u00a0coca\u00edna \u00a0 y \u00a0 en \u00a0 la \u00a0 sentencia \u00a0 de \u00a0 segundo \u00a0 grado, \u00a0por \u00a0\u201ctransportar\u201d \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0esa \u00a0sustancia. \u00a0\u00a0<\/p>\n<p>Agrega \u00a0que \u00a0el \u00a0acusado \u00a0\u201cno \u00a0podr\u00e1 ser \u00a0declarado \u00a0culpable \u00a0por \u00a0hechos que no consten en la acusaci\u00f3n, ni por delitos \u00a0por \u00a0los \u00a0cuales \u00a0no \u00a0se \u00a0ha \u00a0solicitado \u00a0condena\u201d, por lo cual la imputaci\u00f3n \u00a0f\u00e1ctica \u00a0debe \u00a0integrarse, \u00a0armonizar \u00a0y atender a la unidad con la imputaci\u00f3n \u00a0jur\u00eddica, \u00a0m\u00e1xime \u00a0en \u00a0un \u00a0delito \u00a0como \u00a0el \u00a0tr\u00e1fico \u00a0de estupefacientes, que \u00a0contiene \u00a0 en \u00a0 su \u00a0 descripci\u00f3n \u00a0 t\u00edpica \u00a0 varios \u00a0 verbos \u00a0alternativos \u00a0con \u00a0significaci\u00f3n espec\u00edfica. \u00a0\u00a0<\/p>\n<p>\u201cEn \u00a0este caso la sanci\u00f3n penal es igual \u00a0pero \u00a0es \u00a0distinto \u00a0el desvalor de porte que el de tr\u00e1fico de estupefacientes y \u00a0qu\u00e9 \u00a0no \u00a0decir el de transportar por ser ontol\u00f3gica y valorativamente diverso, \u00a0por \u00a0lo \u00a0que \u00a0se \u00a0impone \u00a0al \u00a0fallador \u00a0realizar la correspondiente ponderaci\u00f3n \u00a0conforme \u00a0a \u00a0las \u00a0circunstancias \u00a0de realizaci\u00f3n del hecho, valores, derechos y \u00a0principios constitucionales en conflicto.\u201d \u00a0\u00a0<\/p>\n<p>Solicita \u00a0a \u00a0la \u00a0Corte \u00a0dejar sin efecto el \u00a0fallo \u00a0impugnado y regresar el expediente al Tribunal Superior de Pereira con la \u00a0finalidad \u00a0de \u00a0que \u00a0emita \u00a0una \u00a0\u201cnueva sentencia para que se respete el debido \u00a0proceso y la congruencia.\u201d \u00a0\u00a0<\/p>\n<p>SEGUNDO CARGO: Desconocimiento de las reglas \u00a0de apreciaci\u00f3n probatoria. Falso juicio de identidad \u00a0\u00a0<\/p>\n<p>En criterio del censor, el Ad-quem incurri\u00f3 \u00a0en \u00a0violaci\u00f3n \u00a0indirecta de la ley sustancial por falso juicio de identidad, al \u00a0cercenar \u00a0y \u00a0tergiversar \u00a0los \u00a0testimonios \u00a0de Olga Liliana Gaviria Ruiz, Mar\u00eda \u00a0Lucila \u00a0Acosta \u00a0Arenas, \u00a0Alexandra \u00a0Aponte \u00a0G\u00f3mez \u00a0y Diana Patricia Castrill\u00f3n \u00a0Vanegas, \u00a0y \u00a0la \u00a0denuncia \u00a0instaurara \u00a0ante la Unidad de Polic\u00eda Judicial de la \u00a0Polic\u00eda Nacional de Cartago. \u00a0\u00a0<\/p>\n<p>Transcribe \u00a0 en \u00a0 lo \u00a0 pertinente \u00a0 las \u00a0declaraciones \u00a0 que \u00a0 le \u00a0interesan; \u00a0protesta \u00a0porque \u00a0el \u00a0Ad-quem \u00a0les \u00a0rest\u00f3 \u00a0credibilidad \u00a0por tener inter\u00e9s en favorecer a su pariente implicada; y diserta \u00a0de la siguiente manera: \u00a0\u00a0<\/p>\n<p>2.1 \u00a0Con \u00a0relaci\u00f3n \u00a0al \u00a0testimonio de Olga \u00a0Liliana \u00a0Gaviria \u00a0Ruiz, aclara que no es pariente de la implicada, sino amiga de \u00a0estudios \u00a0de \u00a0una hija de ella; y resalta que dicha testigo acudi\u00f3 a la casa de \u00a0la \u00a0implicada \u00a0para despedirse cuando lleg\u00f3 un muchacho y le pidi\u00f3 el favor de \u00a0que \u00a0le \u00a0llevara unos documentos y una agenda a Espa\u00f1a y que se los entregara a \u00a0otro muchacho llamado Sergio. \u00a0\u00a0<\/p>\n<p>2.2 En su testimonio\u00a0 Alexandra Aponte \u00a0G\u00f3mez, \u00a0nieta \u00a0de \u00a0la acusada, asegur\u00f3 que ella vio cuando Ferney Ortiz Fontal \u00a0le \u00a0entreg\u00f3 \u00a0la \u00a0agenda, \u00a0un \u00a0sobre de manila y unos documentos a su abuela (la \u00a0procesada), \u00a0para \u00a0que \u00a0se \u00a0los \u00a0llevara a Espa\u00f1a; y que adem\u00e1s vio y escuch\u00f3 \u00a0cuando \u00a0su \u00a0abuela, ya detenida en migraci\u00f3n del aeropuerto de Pereira, le dijo \u00a0al \u00a0 polic\u00eda \u00a0 Valencia \u00a0 que \u00a0Ferney \u00a0era \u00a0la \u00a0persona \u00a0que \u00a0le \u00a0entreg\u00f3 \u00a0los \u00a0documentos. \u00a0\u00a0<\/p>\n<p>Esta prueba, dice el libelista, tambi\u00e9n fue \u00a0cercenada \u00a0por \u00a0el Tribunal Superior, por limitarse a decir esa corporaci\u00f3n que \u00a0los \u00a0testimonios \u00a0de \u00a0los parientes de la implicada, entre ellos sus nietas, son \u00a0poco cre\u00edbles, ya que dejan entrever el \u00e1nimo de favorecerla. \u00a0\u00a0<\/p>\n<p>2.3 La procesada MAR\u00cdA LUCILA ACOSTA ARENAS \u00a0decidi\u00f3 \u00a0 declarar \u00a0 bajo \u00a0 juramento, \u00a0 y \u00a0 el \u00a0 Tribunal \u00a0 Superior \u00a0tambi\u00e9n \u00a0\u201ccercen\u00f3\u201d \u00a0su \u00a0versi\u00f3n \u00a0al \u00a0decir \u00a0esa \u00a0corporaci\u00f3n \u00a0que \u00a0\u201cigual \u00a0acontece con la declaraci\u00f3n de la se\u00f1ora ACOSTA ARENAS que \u00a0no \u00a0aporta \u00a0aspectos \u00a0de \u00a0mayor \u00a0importancia, \u00a0pues, s\u00f3lo se trata de excusar y \u00a0desmentir \u00a0las \u00a0versiones \u00a0ofrecidas \u00a0por \u00a0los \u00a0testigos \u00a0de cargo, es decir los \u00a0AGENTES \u00a0DE \u00a0LA \u00a0POLIC\u00cdA que efectuaron la captura, en el sentido, de que desde \u00a0un \u00a0primer momento dijo el nombre de quien le hab\u00eda dado los documentos, cuando \u00a0los \u00a0 \u00a0 gendarmes \u00a0 \u00a0 al \u00a0 \u00a0un\u00edsono \u00a0 \u00a0relataron \u00a0 \u00a0lo \u00a0 \u00a0contrario\u201d \u00a0\u00a0<\/p>\n<p>Recuerda el censor que la implicada relat\u00f3 \u00a0que \u00a0su \u00a0vecino \u00a0Ferney Ortiz Fontal le pidi\u00f3 el favor de que llevara a Espa\u00f1a \u00a0\u201cun \u00a0encargo\u201d, \u00a0unos \u00a0documentos, \u00a0entre \u00a0ellos \u00a0la \u00a0agenda que result\u00f3 con \u00a0droga, \u00a0que \u00a0un \u00a0amigo \u00a0de \u00a0\u00e9l, \u00a0pero \u00a0desconocido \u00a0de ella, iba a enviar y que \u00a0alguien \u00a0llamado \u00a0Sergio \u00a0los \u00a0recibir\u00eda en Madrid. Que ella dijo a la polic\u00eda \u00a0que \u00a0la \u00a0captur\u00f3 \u00a0el \u00a0nombre \u00a0de \u00a0quien \u00a0le \u00a0entreg\u00f3 \u00a0los \u00a0documentos, a quien \u00a0denunci\u00f3 \u00a0 posteriormente, \u00a0seg\u00fan \u00a0copia \u00a0que \u00a0se \u00a0admiti\u00f3 \u00a0formalmente \u00a0como \u00a0prueba. \u00a0\u00a0<\/p>\n<p>2.4 Testimonio de Diana Patricia Castrill\u00f3n \u00a0Vanegas, \u00a0la agente que materializ\u00f3 la captura y rindi\u00f3 el informe de polic\u00eda \u00a0judicial. \u00a0\u00a0<\/p>\n<p>En \u00a0la \u00a0motivaci\u00f3n \u00a0del \u00a0fallo el Tribunal \u00a0Superior \u00a0exclam\u00f3 \u00a0que \u00a0no \u00a0entend\u00eda \u00a0por \u00a0qu\u00e9 \u00a0la implicada no inform\u00f3 a la \u00a0polic\u00eda \u00a0desde \u00a0un \u00a0primer \u00a0momento el nombre del vecino que le hab\u00eda hecho el \u00a0encargo; \u00a0y \u00a0entonces, \u00a0demerit\u00f3 \u00a0las \u00a0narraciones \u00a0de \u00a0la \u00a0procesada \u00a0y de sus \u00a0parientes. \u00a0\u00a0<\/p>\n<p>2.5 \u00a0Sobre \u00a0la \u00a0denuncia formulada el 28 de \u00a0abril \u00a0de \u00a02005 \u00a0por \u00a0la \u00a0procesada \u00a0MAR\u00cdA \u00a0LUCILA ACOSTA ARENAS, contra Ferney \u00a0Ortiz, \u00a0con \u00a0la \u00a0transcripci\u00f3n pertinente el censor se propone demostrar que se \u00a0refer\u00eda \u00a0a los acontecimientos investigados penalmente, al encargo de llevar la \u00a0agenda \u00a0a \u00a0Espa\u00f1a \u00a0y \u00a0a \u00a0la \u00a0captura \u00a0de \u00a0ella en el aeropuerto de Pereira: Sin \u00a0embargo, \u00a0acota \u00a0el \u00a0censor, \u00a0el \u00a0funcionario \u00a0que \u00a0la \u00a0recibi\u00f3 \u201cen \u00a0forma inapropiada calific\u00f3 como Abuso de Confianza\u201d, \u00a0y \u00a0el \u00a0Tribunal \u00a0Superior \u00a0la \u00a0calific\u00f3 de tard\u00eda porque la \u00a0captura \u00a0de la procesada ocurri\u00f3 el 22 de abril del mismo a\u00f1o; y mengu\u00f3 en su \u00a0valor \u00a0probatorio, porque, seg\u00fan Juez colegiado, se hizo por el delito de abuso \u00a0de \u00a0confianza, \u00a0que \u00a0nada tiene que ver con el il\u00edcito investigado \u2013narcotr\u00e1fico-. \u00a0\u00a0<\/p>\n<p>El libelista advera que la\u00a0 denuncia no \u00a0fue \u00a0tard\u00eda, \u00a0pues \u00a0en \u00a0principio \u00a0la \u00a0implicada \u00a0ejerci\u00f3 su derecho a guardar \u00a0silencio; \u00a0 y \u00a0 luego, \u00a0 como \u00a0estaba \u00a0en \u00a0detenci\u00f3n \u00a0domiciliaria, \u00a0no \u00a0pod\u00eda \u00a0movilizarse, \u00a0al \u00a0punto que fue recibida en su domicilio por la SIJIN de Cartago \u00a0(Valle). \u00a0\u00a0<\/p>\n<p>En \u00a0un \u00a0aparte \u00a0del libelo que destina a la \u00a0trascendencia \u00a0de \u00a0los \u00a0yerros, \u00a0el \u00a0casacionista \u00a0sostiene \u00a0que, \u00a0en s\u00edntesis, \u00a0\u201cfueron \u00a0omitidos \u00a0en \u00a0su totalidad\u201d los testimonios de Olga Liliana Gaviria \u00a0Ruiz, \u00a0Alexandra \u00a0Aponte \u00a0G\u00f3mez y Mar\u00eda Lucila Acosta Arenas, quienes en forma \u00a0clara \u00a0y \u00a0de buena fe dijeron que fue un tercero quien entreg\u00f3 subrepticiamente \u00a0el \u00a0alijo a la implicada, quien en forma desprevenida acept\u00f3 llevar el encargo, \u00a0sin revisarlo. \u00a0\u00a0<\/p>\n<p>Tambi\u00e9n \u00a0se \u00a0tergiversaron, \u00a0insiste, \u00a0el \u00a0testimonio \u00a0de \u00a0la \u00a0agente Castrill\u00f3n Vanegas y el escrito de denuncia, pruebas \u00a0que, \u00a0de \u00a0haberse apreciado correctamente habr\u00edan conducido, cuando menos, a la \u00a0aplicaci\u00f3n \u00a0 \u00a0del \u00a0 \u00a0principio \u00a0 \u00a0in \u00a0 dubio \u00a0 pro \u00a0reo. \u00a0\u00a0<\/p>\n<p>Solicita \u00a0a la Corte casar el fallo materia \u00a0del \u00a0recurso \u00a0extraordinario \u00a0y \u00a0en \u00a0su \u00a0lugar, \u00a0proferir \u00a0el de sustituci\u00f3n de \u00a0naturaleza absolutoria. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES \u00a0DE \u00a0LA \u00a0SALA \u00a0\u00a0<\/p>\n<p>La \u00a0demanda \u00a0presentada \u00a0por el defensor de \u00a0MAR\u00cdA \u00a0LUCILA \u00a0ACOSTA \u00a0ARENAS ser\u00e1 inadmitida por las siguientes razones, como \u00a0se \u00a0explicar\u00e1 \u00a0a \u00a0continuaci\u00f3n: \u00a0i) \u00a0no \u00a0satisface \u00a0los requisitos formales ni \u00a0materiales \u00a0establecidos en el art\u00edculo 184 del C\u00f3digo de procedimiento Penal, \u00a0Ley \u00a0906 de 2004; ii) la Sala de Casaci\u00f3n Penal no advierte vulneraci\u00f3n alguna \u00a0de \u00a0las garant\u00edas fundamentales de que son titulares los intervinientes, que la \u00a0Corte \u00a0 debiera \u00a0proteger, \u00a0as\u00ed \u00a0fuere \u00a0oficiosamente, \u00a0en \u00a0los \u00a0t\u00e9rminos \u00a0del \u00a0art\u00edculo \u00a0 6\u00b0 \u00a0 de \u00a0 la \u00a0Constituci\u00f3n \u00a0Pol\u00edtica2 \u00a0 y \u00a0 del \u00a0 art\u00edculo \u00a0 180 \u00a0ib\u00eddem3; \u00a0y iii) no se precisa emitir un nuevo fallo de fondo, por lo cual \u00a0no \u00a0es \u00a0necesario superar los defectos de la demanda en atenci\u00f3n a los fines de \u00a0la \u00a0casaci\u00f3n, \u00a0ni \u00a0por la fundamentaci\u00f3n de los cargos, ni por la posici\u00f3n de \u00a0la \u00a0impugnante \u00a0dentro \u00a0del \u00a0proceso, \u00a0ni \u00a0por \u00a0la \u00a0\u00edndole \u00a0de \u00a0la controversia \u00a0planteada. \u00a0\u00a0<\/p>\n<p>I. \u00a0SOBRE \u00a0EL \u00a0PRIMER \u00a0CARGO: \u00a0Nulidad por \u00a0desconocimiento del debido proceso \u00a0\u00a0<\/p>\n<p>El casacionista sostiene que se desconoci\u00f3 \u00a0el \u00a0debido \u00a0proceso, \u00a0porque \u00a0no \u00a0se hizo claridad respecto del verbo rector del \u00a0delito \u00a0 de \u00a0\u201cfabricaci\u00f3n, \u00a0tr\u00e1fico \u00a0y \u00a0porte \u00a0de \u00a0estupefacientes\u201d \u00a0que \u00a0se \u00a0endilg\u00f3 \u00a0MAR\u00cdA \u00a0LUCILA \u00a0ACOSTA \u00a0ARENAS, \u00a0pues \u00a0en la audiencia preliminar de imputaci\u00f3n la Fiscal\u00eda se \u00a0refiri\u00f3 \u00a0al \u201ctr\u00e1fico\u201d, \u00a0en \u00a0 \u00a0el \u00a0 \u00a0escrito \u00a0 \u00a0de \u00a0 \u00a0acusaci\u00f3n \u00a0 \u00a0se \u00a0 \u00a0menciona \u00a0 el \u00a0 \u201cporte\u201d, \u00a0 la \u00a0 sentencia \u00a0de \u00a0primera \u00a0instancia \u00a0 tambi\u00e9n \u00a0 fue \u00a0 dictada \u00a0 por \u00a0\u201cllevar \u00a0consigo\u201d. \u00a0\u00a0<\/p>\n<p>Y, \u00a0aunque el libelista admite que en este \u00a0evento \u00a0 una \u00a0 u \u00a0 otra \u00a0 expresi\u00f3n \u00a0\u2013tr\u00e1fico, \u00a0porte, \u00a0o \u00a0llevar \u00a0consigo- \u00a0generan los mismos efectos, \u00a0aspira \u00a0a \u00a0que \u00a0se declare la nulidad de lo actuado, a partir de la sentencia de \u00a0segunda \u00a0 instancia, \u00a0 para \u00a0 que \u00a0 se \u00a0 emita \u00a0 un \u00a0 nuevo \u00a0 fallo, \u00a0 que \u00a0 sea \u00a0congruente. \u00a0\u00a0<\/p>\n<p>1.1. \u00a0Como lo ha reiterado esta Sala de la \u00a0Corte, \u00a0el \u00a0recurso \u00a0de \u00a0casaci\u00f3n \u00a0inherente \u00a0al \u00a0sistema acusatorio colombiano \u00a0regido \u00a0por \u00a0la \u00a0Ley \u00a0906 \u00a0de \u00a02004, \u00a0se concibi\u00f3 como un medio de impugnaci\u00f3n \u00a0extraordinario, \u00a0inescindiblemente \u00a0vinculado \u00a0a \u00a0las \u00a0fines \u00a0constitucionales y \u00a0legales \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 mismo4. \u00a0\u00a0<\/p>\n<p>Esas \u00a0finalidades \u00a0de \u00a0la casaci\u00f3n, entre \u00a0ellas, \u00a0la efectividad del derecho material, el respeto de las garant\u00edas de los \u00a0intervinientes \u00a0y la reparaci\u00f3n de los agravios inferidos a \u00e9stos, condicionan \u00a0el \u00a0inter\u00e9s \u00a0de \u00a0quien \u00a0interpone el recurso extraordinario, al punto de tornar \u00a0inadmisible \u00a0la \u00a0demanda \u00a0cuando \u00a0los motivos invocados no se vinculan directa y \u00a0concretamente con alguno de esos fines. \u00a0\u00a0<\/p>\n<p>El interviniente que pretenda que esta Sala \u00a0de \u00a0Corte \u00a0case \u00a0la sentencia de segunda instancia, debe reflejar en forma clara \u00a0el \u00a0inter\u00e9s \u00a0que \u00a0lo \u00a0mueve, puesto que si el libelista no pretende que se haga \u00a0efectivo \u00a0alg\u00fan \u00a0derecho \u00a0material, ni la restauraci\u00f3n de una garant\u00eda, ni la \u00a0reparaci\u00f3n \u00a0de \u00a0un \u00a0agravio, \u00a0entonces \u00a0su \u00a0demanda ser\u00e1 inadmitida, porque en \u00a0tales \u00a0 \u00a0 circunstancias \u00a0 \u00a0 carece \u00a0 \u00a0 de \u00a0 \u00a0sentido \u00a0 \u00a0incoar \u00a0 \u00a0el \u00a0 \u00a0recurso \u00a0extraordinario. \u00a0\u00a0<\/p>\n<p>1.2 \u00a0En \u00a0el \u00a0presente \u00a0asunto, sin indicar \u00a0cu\u00e1l \u00a0es el inter\u00e9s que lo motiva, ni el beneficio concreto que obtendr\u00eda, el \u00a0defensor \u00a0de \u00a0la \u00a0implicada \u00a0MARTHA \u00a0LUCILA \u00a0ACOSTA \u00a0ARENAS pretende se deje sin \u00a0efecto \u00a0la sentencia de segunda instancia, sencillamente para que se profiera un \u00a0nuevo \u00a0fallo, \u00a0donde \u00a0se \u00a0diga \u00a0que \u00a0la \u00a0condena \u00a0se imparte por \u201cporte\u201d de estupefacientes, como qued\u00f3 \u00a0sentado \u00a0en \u00a0el \u00a0escrito de acusaci\u00f3n y como le fue imputado en la audiencia de \u00a0acusaci\u00f3n, \u00a0 \u00a0en \u00a0 \u00a0lugar \u00a0 \u00a0de \u00a0 \u00a0utilizar \u00a0 la \u00a0 expresi\u00f3n \u00a0 \u201cllevar \u00a0consigo\u201d, que fue utilizada en \u00a0la decisi\u00f3n de primer grado que confirm\u00f3 el Tribunal Superior. \u00a0\u00a0<\/p>\n<p>Pero \u00a0ocurre \u00a0que el libelista no explic\u00f3 \u00a0cu\u00e1l \u00a0 \u00a0 es \u00a0 \u00a0la \u00a0 \u00a0diferencia \u00a0 \u00a0entre \u00a0 \u00a0la \u00a0 \u00a0expresi\u00f3n \u00a0 \u00a0\u201cporte\u201d \u00a0 de \u00a0 estupefacientes \u00a0 y \u00a0la \u00a0expresi\u00f3n \u00a0 \u00a0 \u00a0\u201cllevar \u00a0 \u00a0 consigo\u201d \u00a0 estupefacientes, \u00a0 ni \u00a0 en \u00a0 t\u00e9rminos \u00a0 ling\u00fc\u00edsticos, \u00a0 ni \u00a0conceptualmente, \u00a0ni \u00a0en sentido normativo, ni con relaci\u00f3n a las consecuencias \u00a0jur\u00eddicas de la utilizaci\u00f3n de una u otra. \u00a0\u00a0<\/p>\n<p>Vale \u00a0 decir, \u00a0el \u00a0censor \u00a0pretende \u00a0una \u00a0correcci\u00f3n \u00a0del \u00a0fallo \u00a0de segunda instancia, como si se empe\u00f1ara en velar por \u00a0alguna \u00a0f\u00f3rmula \u00a0sacramental exclusiva que hubiese debido utilizarse, o como si \u00a0le \u00a0preocupara \u00a0la indemnidad de las formas por la forma misma, ignorando que el \u00a0procedimentalismo \u00a0no \u00a0es \u00a0un \u00a0fin en s\u00ed mismo, sino una especie de veh\u00edculo a \u00a0trav\u00e9s \u00a0del \u00a0cual \u00a0se \u00a0llega \u00a0racionalmente \u00a0a \u00a0la \u00a0efectividad de los derechos \u00a0sustanciales. \u00a0\u00a0<\/p>\n<p>Por manera que, no se vislumbra el inter\u00e9s \u00a0que \u00a0asiste \u00a0al \u00a0defensor al instaurar el recurso extraordinario de casaci\u00f3n, y \u00a0la \u00a0demanda pr\u00e1cticamente se reduce al planteamiento del presunto problema, sin \u00a0avanzar hasta la sustentaci\u00f3n razonable del cargo. \u00a0\u00a0<\/p>\n<p>1.3 \u00a0De \u00a0otra \u00a0parte, la Sala de Casaci\u00f3n \u00a0Penal \u00a0no \u00a0observa la necesidad de un nuevo fallo, porque no existen diferencias \u00a0que \u00a0produzcan \u00a0consecuencias \u00a0jur\u00eddicas \u00a0entre las expresiones \u201cporte\u201d \u00a0 \u00a0de \u00a0 \u00a0estupefacientes \u00a0 \u00a0y \u00a0\u201cllevar \u00a0 \u00a0consigo\u201d \u00a0estupefacientes, \u00a0 \u00a0 \u00a0pues \u00a0 \u00a0 \u00a0portar \u00a0 \u00a0y \u00a0 \u00a0llevar \u00a0 \u00a0consigo \u00a0no \u00a0son \u00a0conceptos normativos, sino expresiones comunes que en el \u00a0caso \u00a0de \u00a0la \u00a0implicada \u00a0MAR\u00cdA LUCILA ACOSTA ARENAS se aviene v\u00e1lidamente como \u00a0sin\u00f3nimas, debido a que generan los mismos efectos jur\u00eddicos. \u00a0\u00a0<\/p>\n<p>En \u00a0s\u00edntesis, \u00a0no \u00a0se \u00a0postul\u00f3 \u00a0reparo \u00a0condigno \u00a0a \u00a0la \u00a0naturaleza del recurso extraordinario de casaci\u00f3n, que la Sala \u00a0pueda admitir. \u00a0\u00a0<\/p>\n<p>II. \u00a0SOBRE \u00a0EL SEGUNDO \u00a0CARGO. Falsos juicios de identidad \u00a0\u00a0<\/p>\n<p>Dice \u00a0el \u00a0censor \u00a0que el Tribunal Superior \u00a0cercen\u00f3 \u00a0los \u00a0medios \u00a0de \u00a0prueba \u00a0que \u00a0menciona, \u00a0testimonios e informes, hasta \u00a0llevarlos \u00a0a \u00a0producir \u00a0consecuencias \u00a0negativas \u00a0para la implicada, que en sana \u00a0cr\u00edtica no su hubiesen obtenido. \u00a0\u00a0<\/p>\n<p>Se \u00a0observa que la protesta dice relaci\u00f3n \u00a0con \u00a0el \u00a0poder \u00a0suasorio \u00a0atribuido a las declaraciones y a los documentos, pero \u00a0sin \u00a0 \u00a0 demostrar \u00a0 \u00a0 el \u00a0 \u00a0 falso \u00a0 \u00a0juicio \u00a0 \u00a0de \u00a0identidad \u00a0por \u00a0cercenamiento, \u00a0recorte o adici\u00f3n de \u00a0esos medios de prueba. \u00a0\u00a0<\/p>\n<p>2.1. \u00a0El \u00a0falso \u00a0juicio \u00a0de \u00a0identidad supone que el juzgador tiene en \u00a0cuenta \u00a0un \u00a0medio \u00a0probatorio \u00a0legal y oportunamente practicado; no obstante, al \u00a0sopesarlo \u00a0lo \u00a0distorsiona, \u00a0tergiversa, \u00a0recorta \u00a0o \u00a0adiciona \u00a0en \u00a0su contenido \u00a0literal. \u00a0\u00a0<\/p>\n<p>En ese evento, el censor tiene la carga de \u00a0confrontar \u00a0por \u00a0separado \u00a0el \u00a0tenor \u00a0literal \u00a0de \u00a0cada prueba sobre la que hace \u00a0recaer \u00a0el \u00a0yerro, \u00a0con \u00a0lo \u00a0que \u00a0el Ad-quem pens\u00f3 que ellas dec\u00edan; y una vez \u00a0demostrado \u00a0el \u00a0desfase, \u00a0debe \u00a0continuar \u00a0hacia \u00a0la \u00a0trascendencia \u00a0de \u00a0aquella \u00a0impropiedad. \u00a0\u00a0<\/p>\n<p>En \u00a0otras \u00a0palabras, quien as\u00ed alega debe \u00a0comparar \u00a0puntualmente \u00a0lo dicho por los testigos, o lo indicado por las pruebas \u00a0de \u00a0otras \u00a0especies, \u00a0con lo que el Tribunal Superior ley\u00f3 en esas espec\u00edficas \u00a0versiones \u00a0testimoniales, \u00a0o \u00a0con \u00a0lo \u00a0que entendi\u00f3 que indicaban las restantes \u00a0pruebas; \u00a0todo \u00a0con \u00a0el \u00a0fin \u00a0de \u00a0demostrar que el fallo se ha distanciado de la \u00a0realidad \u00a0objetivamente \u00a0declarada \u00a0por \u00a0el \u00a0acopio probatorio, por distorsi\u00f3n, \u00a0recorte o adici\u00f3n en su contenido material. \u00a0\u00a0<\/p>\n<p>2.2 \u00a0La \u00a0estructuraci\u00f3n \u00a0de la censura en \u00a0punto \u00a0 \u00a0de \u00a0 la \u00a0 trascendencia \u00a0 del \u00a0 error \u00a0 de \u00a0 hecho \u00a0 por \u00a0 falso \u00a0juicio \u00a0de \u00a0identidad no se cumple \u00a0con \u00a0la manifestaci\u00f3n que al respecto haga el libelista, como si de su opini\u00f3n \u00a0personal \u00a0se \u00a0tratara; \u00a0pues, \u00a0de \u00a0bastar \u00a0aquel \u00a0tipo \u00a0de \u00a0cr\u00edtica \u00a0el recurso \u00a0extraordinario no distar\u00eda en mucho de un alegato de instancia. \u00a0\u00a0<\/p>\n<p>La \u00a0demostraci\u00f3n \u00a0de la trascendencia del \u00a0yerro \u00a0atribuido \u00a0al \u00a0Ad-quem comporta la obligaci\u00f3n de ense\u00f1ar a la Corte que \u00a0si \u00a0tal \u00a0falencia no se hubiese presentado, entonces el sentido del fallo ser\u00eda \u00a0distinto; \u00a0y \u00a0para \u00a0ello \u00a0es \u00a0preciso \u00a0demostrar que si la prueba cuestionada se \u00a0hubiese \u00a0apreciado \u00a0en \u00a0forma \u00a0correcta, \u00a0las restantes pruebas sopesadas por el \u00a0Tribunal \u00a0perder\u00edan \u00a0la \u00a0entidad \u00a0jur\u00eddica \u00a0necesaria \u00a0y suficiente para mover \u00a0hacia la convicci\u00f3n declarada en el fallo. \u00a0\u00a0<\/p>\n<p>En \u00a0 otras \u00a0palabras, \u00a0en \u00a0este \u00a0evento, \u00a0correspond\u00eda \u00a0al \u00a0casacionista \u00a0referirse al verdadero sentido y alcance de las \u00a0pruebas \u00a0supuestamente \u00a0cercenadas, \u00a0y adem\u00e1s demostrar que aquellas, aunadas a \u00a0todas \u00a0las dem\u00e1s analizadas en el fallo, no permit\u00edan arribar a la convicci\u00f3n \u00a0de certeza sobre la responsabilidad penal de la procesada. \u00a0\u00a0<\/p>\n<p>Ahora bien, desvirtuar el m\u00e9rito concedido \u00a0a \u00a0las \u00a0otras pruebas implica a su vez demostrar que los funcionarios judiciales \u00a0erraron \u00a0en \u00a0el proceso de valoraci\u00f3n y fijaci\u00f3n de su poder suasorio, lo cual \u00a0tampoco \u00a0se \u00a0logra \u00a0a \u00a0trav\u00e9s \u00a0de \u00a0la \u00a0imposici\u00f3n \u00a0del criterio particular del \u00a0censor, \u00a0sino \u00a0demostrando con la l\u00f3gica casacional la incursi\u00f3n en errores de \u00a0hecho o de derecho en ese ejercicio. \u00a0\u00a0<\/p>\n<p>2.3. \u00a0 En \u00a0este \u00a0caso, \u00a0el \u00a0casacionista \u00a0transcribi\u00f3 \u00a0el \u00a0documento, \u00a0los testimonios que le interesan y los apartes del \u00a0fallo \u00a0relativos \u00a0a \u00a0los \u00a0mismos, \u00a0pero \u00a0no con el fin de ense\u00f1ar alguna de las \u00a0modalidades \u00a0del \u00a0falso juicio de identidad, esto es, tergiversaci\u00f3n, recorte o \u00a0adici\u00f3n, \u00a0sino \u00a0para \u00a0insistir \u00a0en que de esas pruebas ten\u00eda que deducirse que \u00a0MAR\u00cdA \u00a0LUCILA \u00a0ACOSTA \u00a0ARENAS \u00a0actu\u00f3 \u00a0de \u00a0buena fe, que simplemente accedi\u00f3 a \u00a0llevar \u00a0un \u00a0encargo \u00a0a \u00a0Espa\u00f1a, \u00a0ignorando \u00a0su \u00a0contenido, como lo dijo en todo \u00a0momento; \u00a0y \u00a0que, \u00a0por \u00a0tanto, \u00a0ha debido absolverse, as\u00ed fuera por ausencia de \u00a0certeza acerca de su responsabilidad penal. \u00a0\u00a0<\/p>\n<p>Y como el Ad-quem arrib\u00f3 a la conclusi\u00f3n \u00a0contraria, \u00a0es \u00a0decir \u00a0encontr\u00f3 certeza para condenar, es ese convencimiento en \u00a0contrario \u00a0lo \u00a0que \u00a0el \u00a0libelista \u00a0califica como falso \u00a0juicio \u00a0de identidad, manifestando lo que a bien tiene \u00a0acerca \u00a0 de \u00a0las \u00a0motivaciones \u00a0del \u00a0fallo, \u00a0sin \u00a0referencia \u00a0espec\u00edfica \u00a0a \u00a0la \u00a0tergiversaci\u00f3n, \u00a0adici\u00f3n \u00a0o \u00a0cercenamiento \u00a0de \u00a0alguna prueba que hubiese sido \u00a0defectuosamente \u00a0apreciada, \u00a0al punto que redunda en comentarios generales, pero \u00a0sin \u00a0concentrarse \u00a0en \u00a0demostrar \u00a0en \u00a0qu\u00e9 consisten los errores de hecho que le \u00a0atribuye. \u00a0\u00a0<\/p>\n<p>En \u00a0 lugar \u00a0 de \u00a0 aproximarse \u00a0 a \u00a0 una \u00a0argumentaci\u00f3n \u00a0de \u00a0esa naturaleza, el apoderado de MAR\u00cdA LUCILA ACOSTA ARENAS, \u00a0s\u00f3lo \u00a0transcribi\u00f3 \u00a0las pruebas cuya valoraci\u00f3n reclama err\u00f3nea, pero no hizo \u00a0referencia \u00a0a \u00a0la \u00a0capacidad \u00a0intr\u00ednseca \u00a0de \u00a0las \u00a0mismas \u00a0para \u00a0desvirtuar \u00a0el \u00a0pensamiento \u00a0 \u00a0 \u00a0\u2013 \u00a0supuestamente \u00a0errado- \u00a0del \u00a0Tribunal \u00a0Superior, \u00a0quedando \u00a0entonces \u00a0aisladas y \u00a0vac\u00edas \u00a0de \u00a0contenido \u00a0las \u00a0expresiones que promulgan la idea seg\u00fan la cual de \u00a0tales \u00a0medios \u00a0no \u00a0dimanaba \u00a0la \u00a0certeza \u00a0de \u00a0la \u00a0responsabilidad \u00a0penal \u00a0de \u00a0la \u00a0procesada. \u00a0\u00a0<\/p>\n<p>2.4 \u00a0Las \u00a0impropiedades \u00a0advertidas \u00a0con \u00a0antelaci\u00f3n \u00a0conllevan \u00a0a \u00a0inadmitir la demanda en cuanto hace al segundo cargo, \u00a0m\u00e1xime \u00a0que \u00a0el \u00a0libelista tampoco aborda el an\u00e1lisis cr\u00edtico de los indicios \u00a0que \u00a0cimientan \u00a0el \u00a0fallo; y que en la revisi\u00f3n del expediente no se observa la \u00a0vulneraci\u00f3n \u00a0de \u00a0alguna \u00a0garant\u00eda fundamental, que amerite el ejercicio de las \u00a0facultades \u00a0oficiosas \u00a0de \u00a0la \u00a0Sala \u00a0de \u00a0Casaci\u00f3n \u00a0Penal \u00a0en \u00a0los t\u00e9rminos del \u00a0art\u00edculo 184 del C\u00f3digo de Procedimiento Penal, Ley 906 de 2004. \u00a0\u00a0<\/p>\n<p>III. \u00a0EL \u00a0MECANISMO DE \u00a0INSISTENCIA \u00a0\u00a0<\/p>\n<p>De \u00a0conformidad con el art\u00edculo 184 de la \u00a0Ley \u00a0 906 \u00a0 de \u00a02004, \u00a0y \u00a0seg\u00fan \u00a0lo \u00a0ha \u00a0venido \u00a0reiterando \u00a0esta \u00a0Sala \u00a0de \u00a0la \u00a0Corte5, \u00a0contra \u00a0el \u00a0presente \u00a0auto \u00a0procede \u00a0el \u00a0mecanismo \u00a0especial \u00a0de \u00a0insistencia, \u00a0 \u00a0dentro \u00a0 \u00a0de \u00a0 \u00a0los \u00a0 \u00a0cinco \u00a0 (5) \u00a0 d\u00edas \u00a0 siguientes \u00a0 a \u00a0 su \u00a0notificaci\u00f3n. \u00a0\u00a0<\/p>\n<p>La \u00a0solicitud \u00a0de \u00a0insistencia \u00a0podr\u00e1 ser \u00a0provocada \u00a0oficiosamente \u00a0por \u00a0alguno \u00a0de \u00a0los \u00a0magistrados \u00a0disidentes, \u00a0si \u00a0lo \u00a0hubiere, \u00a0o \u00a0por \u00a0los \u00a0Delegados \u00a0del \u00a0Ministerio \u00a0P\u00fablico \u00a0para \u00a0la \u00a0Casaci\u00f3n \u00a0Penal. \u00a0\u00a0<\/p>\n<p>De \u00a0igual manera, si fuere de su inter\u00e9s, \u00a0el \u00a0demandante \u00a0en \u00a0casaci\u00f3n \u00a0podr\u00e1 elevar su solicitud de insistencia ante el \u00a0Ministerio \u00a0P\u00fablico, a trav\u00e9s de sus Delegados para la Casaci\u00f3n Penal, o ante \u00a0uno \u00a0de \u00a0los \u00a0magistrados \u00a0que \u00a0salvaren \u00a0el \u00a0voto \u00a0en \u00a0cuanto \u00a0a \u00a0la \u00a0decisi\u00f3n \u00a0mayoritaria \u00a0de \u00a0inadmitir \u00a0el \u00a0libelo, \u00a0o \u00a0no \u00a0hubiese \u00a0asistido \u00a0a la Sala por \u00a0cualquier motivo. \u00a0\u00a0<\/p>\n<p>En \u00a0m\u00e9rito \u00a0de \u00a0lo \u00a0expuesto, \u00a0la Sala de \u00a0Casaci\u00f3n Penal de la Corte Suprema de Justicia, \u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0\u00a0<\/p>\n<p>INADMITIR \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada \u00a0a nombre de MAR\u00cdA \u00a0LUCILA ACOSTA ARENAS. \u00a0\u00a0<\/p>\n<p>De \u00a0conformidad \u00a0con \u00a0lo \u00a0dispuesto \u00a0en el \u00a0art\u00edculo \u00a0184 \u00a0de \u00a0la \u00a0Ley \u00a0906 \u00a0de \u00a02004, \u00a0es \u00a0facultad \u00a0del demandante elevar \u00a0petici\u00f3n \u00a0de \u00a0insistencia, \u00a0seg\u00fan \u00a0lo \u00a0indicado \u00a0en \u00a0la \u00a0parte \u00a0motiva de este \u00a0auto. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0notif\u00edquese, \u00a0devu\u00e9lvase \u00a0al \u00a0Tribunal de origen y c\u00famplase. \u00a0\u00a0<\/p>\n<p>MAURO SOLARTE PORTILLA \u00a0<\/p>\n<p>SIGIFREDO \u00a0 ESPINOSA \u00a0P\u00c9REZ \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0ALFREDO G\u00d3MEZ QUINTERO \u00a0\u00a0<\/p>\n<p>Salvamento parcial de voto \u00a0<\/p>\n<p>EDGAR \u00a0 LOMBANA \u00a0 TRUJILLO \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00c1LVARO O. P\u00c9REZ PINZ\u00d3N \u00a0\u00a0<\/p>\n<p>MARINA \u00a0 PULIDO \u00a0 DE \u00a0BAR\u00d3N \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0JORGE LUIS QUINTERO MILAN\u00c9S \u00a0\u00a0<\/p>\n<p>YESID \u00a0 RAM\u00cdREZ \u00a0 BASTIDAS \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0JAVIER ZAPATA ORTIZ \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 \u00a0Seg\u00fan \u00a0consta \u00a0en \u00a0el \u00a0DVD anexo, archivo denominado \u201caudiencia legalizaci\u00f3n \u00a0captura, formulaci\u00f3n imputaci\u00f3n, medida de aseguramiento.\u201d \u00a0\u00a0<\/p>\n<p>2 \u00a0El \u00a0art\u00edculo \u00a06 \u00a0Superior \u00a0establece \u00a0que \u00a0las \u00a0autoridades de la Rep\u00fablica est\u00e1n \u00a0instituidas \u00a0para \u00a0proteger, entre otras cosas, los derechos y libertades de las \u00a0personas. \u00a0\u00a0<\/p>\n<p>3 \u00a0El \u00a0art\u00edculo \u00a0180 \u00a0del C\u00f3digo de Procedimiento Penal, Ley 906 de 2004, se\u00f1ala que \u00a0la \u00a0casaci\u00f3n \u00a0tiene \u00a0por \u00a0finalidades \u00a0la \u00a0efectividad del derecho material, el \u00a0respeto \u00a0de las garant\u00edas de los intervinientes, la reparaci\u00f3n de los agravios \u00a0inferidos a \u00e9stos, y la unificaci\u00f3n de la jurisprudencia. \u00a0\u00a0<\/p>\n<p>4 Sala \u00a0de \u00a0 Casaci\u00f3n \u00a0 Penal. \u00a0 Auto \u00a0 del \u00a0 12 \u00a0de \u00a0diciembre \u00a0de \u00a02005. \u00a0Radicaci\u00f3n \u00a024193. \u00a0\u00a0<\/p>\n<p>5 Sala \u00a0de \u00a0Casaci\u00f3n Penal. Auto del 12 de diciembre de 2005, radicaci\u00f3n 24322; y Auto \u00a0del 10 de mayo de 2006, radicaci\u00f3n 25354. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 25119 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA \u00a0 DE \u00a0 CASACI\u00d3N \u00a0PENAL \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0Magistrado \u00a0Ponente \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Dr. EDGAR LOMBANA TRUJILLO \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Aprobado Acta No. 057 \u00a0\u00a0 Bogot\u00e1 \u00a0D. C., diecis\u00e9is (16) de junio de \u00a0dos mil seis (2006). \u00a0\u00a0 VISTOS \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-11492","post","type-post","status-publish","format-standard","hentry","category-14"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/11492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=11492"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/11492\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=11492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=11492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=11492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}