{"id":11370,"date":"2023-09-08T19:53:05","date_gmt":"2023-09-08T19:53:05","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2491325-05-06-1\/"},"modified":"2023-09-08T19:53:05","modified_gmt":"2023-09-08T19:53:05","slug":"2491325-05-06-1","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2491325-05-06-1\/","title":{"rendered":"24913(25-05-06)-1"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 24913 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>Magistrado ponente: \u00a0<\/p>\n<p>YESID \u00a0 \u00a0RAM\u00cdREZ \u00a0BASTIDAS \u00a0\u00a0<\/p>\n<p>Aprobado \u00a0 Acta \u00a0 N\u00b0 \u00a0051 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D. C., veinticinco (25) de mayo de \u00a0dos mil seis (2006). \u00a0\u00a0<\/p>\n<p>V I S T O S \u00a0<\/p>\n<p>Se procede a resolver sobre la admisibilidad \u00a0de \u00a0la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0presentada por el defensor del procesado H\u00c1ROLD \u00a0IV\u00c1N \u00a0GRANADA \u00a0GARZ\u00d3N \u00a0condenado \u00a0en \u00a0fallos proferidos por el Juzgado Primero \u00a0Penal \u00a0del \u00a0Circuito \u00a0de Ibagu\u00e9 y el Tribunal Superior de la misma ciudad, como \u00a0autor \u00a0penalmente \u00a0responsable \u00a0de \u00a0la conducta punible de homicidio agravado en \u00a0concurso \u00a0con \u00a0lesiones personales, hurto calificado y agravado, y fabricaci\u00f3n, \u00a0tr\u00e1fico y porte de armas de fuego o municiones. \u00a0\u00a0<\/p>\n<p>HECHOS\u00a0 \u00a0 Y\u00a0 \u00a0 ACTUACI\u00d3N\u00a0 \u00a0PROCESAL \u00a0\u00a0<\/p>\n<p>1. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Los primeros fueron descritos en el fallo \u00a0de segunda instancia de la siguiente manera: \u00a0\u00a0<\/p>\n<p>\u201cEl \u00a013 \u00a0de abril de 2002, la Fiscal\u00eda 24 \u00a0Seccional \u00a0ante \u00a0la \u00a0Unidad de Reacci\u00f3n Inmediata (URI), dispuso la apertura de \u00a0una \u00a0investigaci\u00f3n preliminar con el fin de establecer los hechos en los que se \u00a0le \u00a0ocasion\u00f3 \u00a0la \u00a0muerte \u00a0en \u00a0forma \u00a0violenta al se\u00f1or Pedro Antonio Mart\u00ednez \u00a0Galindo, \u00a0 \u00a0 \u00a0 en \u00a0 \u00a0 \u00a0 un \u00a0 \u00a0 \u00a0 \u2018atraco\u2019 \u00a0con \u00a0armas \u00a0de \u00a0fuego en la carrera 4\u00aa Taman\u00e1 con calle 25 de esta ciudad (Ibagu\u00e9, \u00a0aclara \u00a0la \u00a0Sala), \u00a0cuando \u00a0aquel \u00a0se \u00a0desplazaba \u00a0en \u00a0un autom\u00f3vil de servicio \u00a0particular, \u00a0en \u00a0las \u00a0horas \u00a0del \u00a0medio \u00a0d\u00eda \u00a0del \u00a011 \u00a0del \u00a0aludido mes y a\u00f1o, \u00a0despoj\u00e1ndolo \u00a0 de \u00a0 la \u00a0suma \u00a0de \u00a0$15\u2019000.000.00 \u00a0que \u00a0acababa \u00a0de retirar de una entidad bancaria. En esa \u00a0misma \u00a0oportunidad \u00a0result\u00f3 \u00a0lesionada la se\u00f1ora GLORIA MAR\u00cdA LOZANO RINC\u00d3N, \u00a0esposa \u00a0del \u00a0anterior \u00a0y \u00a0quien \u00a0tambi\u00e9n \u00a0viajaba \u00a0en el interior del se\u00f1alado \u00a0automotor (fl. 2 fte. Cuaderno original N\u00b0 1 de este proceso).\u201d \u00a0\u00a0<\/p>\n<p>2. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Abierta la investigaci\u00f3n, fue vinculado \u00a0mediante \u00a0indagatoria \u00a0H\u00c1ROLD \u00a0IV\u00c1N GRANADA GARZ\u00d3N a quien se le resolvi\u00f3 la \u00a0situaci\u00f3n \u00a0jur\u00eddica \u00a0con \u00a0medida detentiva sin excarcelaci\u00f3n, por los delitos \u00a0de \u00a0homicidio \u00a0agravado, \u00a0lesiones \u00a0personales, \u00a0hurto \u00a0calificado y agravado, y \u00a0fabricaci\u00f3n, tr\u00e1fico y porte de armas de fuego o municiones. \u00a0\u00a0<\/p>\n<p>3. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Posteriormente la Fiscal\u00eda Once Delegada \u00a0ante \u00a0los \u00a0Juzgados \u00a0Penales \u00a0del \u00a0Circuito de Ibagu\u00e9, en resoluci\u00f3n del 23 de \u00a0septiembre \u00a0de \u00a02002, \u00a0calific\u00f3 \u00a0el \u00a0m\u00e9rito \u00a0del sumario con acusaci\u00f3n por el \u00a0concurso \u00a0de \u00a0conductas \u00a0punibles \u00a0antes \u00a0especificado \u00a0y \u00a0mantuvo \u00a0la medida de \u00a0aseguramiento al procesado mencionado. \u00a0\u00a0<\/p>\n<p>4. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0El \u00a031 \u00a0de \u00a0marzo \u00a0de \u00a02004, \u00a0el Juzgado \u00a0Primero \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Ibagu\u00e9 profiri\u00f3 sentencia en que conden\u00f3 a \u00a0H\u00c1ROLD \u00a0IV\u00c1N GRANADA GARZ\u00d3N a la pena principal de treinta y dos (32) a\u00f1os y \u00a0nueve \u00a0(9) \u00a0a\u00f1os \u00a0de prisi\u00f3n, y a la pena accesoria de inhabilitaci\u00f3n para el \u00a0ejercicio \u00a0de \u00a0derechos \u00a0y \u00a0funciones \u00a0p\u00fablicas \u00a0por un t\u00e9rmino de veinte (20) \u00a0a\u00f1os, \u00a0 sanciones \u00a0cuya \u00a0ejecuci\u00f3n \u00a0orden\u00f3 \u00a0simult\u00e1neamente \u00a0en \u00a0el \u00a0recinto \u00a0carcelario. \u00a0\u00a0<\/p>\n<p>Adicionalmente \u00a0le \u00a0impuso la obligaci\u00f3n de \u00a0pagar \u00a0solidariamente \u00a0con \u00a0quienes \u00a0llegaren \u00a0a \u00a0ser \u00a0condenados penalmente las \u00a0siguientes \u00a0sumas: \u00a0a \u00a0favor \u00a0de las personas llamadas a suceder al occiso Pedro \u00a0Antonio \u00a0Mart\u00ednez Galindo seiscientos (600) salarios m\u00ednimos legales mensuales \u00a0vigentes; \u00a0a favor de Gloria Mar\u00eda Lozano quince (15) salarios m\u00ednimos legales \u00a0mensuales \u00a0vigentes; \u00a0y a favor de los sucesores de Pedro Antonio Mart\u00ednez y de \u00a0los \u00a0ciudadanos \u00a0Carlos \u00a0Javier \u00a0Uma\u00f1a \u00a0Pascuas \u00a0y \u00a0Gustavo \u00a0Carrizosa, \u00a0quince \u00a0millones \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 pesos \u00a0 \u00a0 ($15\u2019000.000.00). \u00a0\u00a0<\/p>\n<p>5. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0La \u00a0providencia anterior fue apelada por \u00a0H\u00c1ROLD \u00a0IV\u00c1N \u00a0GRANADA \u00a0GARZ\u00d3N \u00a0y \u00a0su \u00a0defensor, \u00a0y \u00a0el 31 de marzo de 2005 el \u00a0Tribunal \u00a0Superior de Ibagu\u00e9 la confirm\u00f3, mediante el fallo objeto del recurso \u00a0extraordinario \u00a0de \u00a0casaci\u00f3n \u00a0interpuesto \u00a0por \u00a0el \u00a0sujeto procesal nombrado en \u00a0\u00faltimo t\u00e9rmino. \u00a0\u00a0<\/p>\n<p>LA\u00a0 DEMANDA : \u00a0<\/p>\n<p>El casacionista postula cuatro cargos contra \u00a0la \u00a0sentencia \u00a0proferida \u00a0por \u00a0el \u00a0Ad quem, as\u00ed: \u00a0\u00a0<\/p>\n<p>Primer reparo: \u00a0<\/p>\n<p>Lo \u00a0enmarca \u00a0dentro \u00a0de la causal tercera de \u00a0casaci\u00f3n \u00a0 prevista \u00a0 en \u00a0 el \u00a0 art\u00edculo \u00a0207, \u00a0numeral \u00a03\u00b0 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0por \u00a0considerar \u00a0que \u00a0la sentencia se dict\u00f3 en un juicio \u00a0viciado \u00a0de \u00a0acuerdo \u00a0con \u00a0lo \u00a0previsto en los art\u00edculos 29 de la Constituci\u00f3n \u00a0Pol\u00edtica, \u00a0 6\u00b0 \u00a0 del \u00a0C\u00f3digo \u00a0Penal, \u00a0y \u00a0306, \u00a0numeral \u00a03\u00b0 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, esto es, por violaci\u00f3n del debido proceso \u201c&#8230;encarnado \u00a0en \u00a0la \u00a0investigaci\u00f3n \u00a0integral&#8230;\u201d, \u00a0principio consagrado en el art\u00edculo 20 \u00a0del \u00a0C\u00f3digo de Procedimiento Penal,\u00a0 y del derecho de defensa en raz\u00f3n de \u00a0haberse \u00a0negado \u00a0la practica de pruebas \u201c&#8230;sustanciales encaminadas a excluir \u00a0o \u00a0 atenuar \u00a0 la \u00a0 responsabilidad \u00a0 del \u00a0 acusado\u201d, \u00a0 decretadas \u00a0dentro \u00a0del \u00a0proceso. \u00a0\u00a0<\/p>\n<p>Estima indispensable el arribo del historial \u00a0de \u00a0la \u00a0motocicleta \u00a0utilizada \u00a0en \u00a0el \u00a0hurto \u00a0averiguado \u00a0y el recaudo de otros \u00a0elementos \u00a0que \u00a0permitan \u00a0establecer \u00a0qu\u00e9 \u00a0personas ten\u00edan v\u00ednculos con dicho \u00a0veh\u00edculo, \u00a0no \u00a0s\u00f3lo \u00a0en \u00a0esta ciudad sino en otras como Medell\u00edn e Ibagu\u00e9, a \u00a0trav\u00e9s \u00a0de los comparendos recientes o concomitantes a la \u00e9poca delictual, con \u00a0el \u00a0fin de conocer qui\u00e9nes se desplazaban en ella al momento de su consumaci\u00f3n \u00a0y \u00a0fueron \u00a0los \u00a0verdaderos \u00a0autores de los delitos investigados, material que no \u00a0obstante \u00a0favorecer al procesado los funcionarios p\u00fablicos se negaron a arribar \u00a0por desidia, afectando de esta manera el derecho de defensa. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Considera \u00a0que \u00a0el \u00a0saneamiento \u00a0de \u00a0este vicio s\u00f3lo puede lograrse \u00a0mediante \u00a0la \u00a0declaratoria \u00a0de nulidad a partir de la resoluci\u00f3n que orden\u00f3 la \u00a0clausura \u00a0de la investigaci\u00f3n, en la medida en que repercuti\u00f3 en la validez de \u00a0la \u00a0actuaci\u00f3n y en la declaraci\u00f3n de justicia contenida en el fallo impugnado, \u00a0y \u00a0por \u00a0no \u00a0contarse con otro remedio para subsanarlo, lo cual conllevar\u00eda a la \u00a0libertad \u00a0inmediata \u00a0de \u00a0H\u00c1ROLD \u00a0IV\u00c1N \u00a0GRANADA \u00a0GARZ\u00d3N, \u00a0en \u00a0aplicaci\u00f3n \u00a0del \u00a0art\u00edculo 365, numeral 4\u00b0 del C\u00f3digo de Procedimiento Penal. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Segundo reproche: \u00a0\u00a0<\/p>\n<p>Al \u00a0amparo de la causal tercera de casaci\u00f3n \u00a0censura \u00a0la \u00a0sentencia recurrida por considerar que fue proferida con violaci\u00f3n \u00a0del \u00a0derecho \u00a0de \u00a0defensa \u00a0de su representado quien fue vinculado al proceso con \u00a0base \u00a0en \u00a0una \u00a0prueba \u00a0nula \u00a0de \u00a0pleno derecho por ser \u201clegalmente prohibida o \u00a0ineficaz\u201d, \u00a0cuya exclusi\u00f3n se impone a tono con el inciso final del art\u00edculo \u00a029 de la Constituci\u00f3n Pol\u00edtica. \u00a0\u00a0<\/p>\n<p>Se \u00a0trata \u00a0del \u00a0reconocimiento \u00a0fotogr\u00e1fico \u00a0realizado \u00a0por \u00a0funcionarios de la Polic\u00eda Judicial en ejercicio de la facultad \u00a0que \u00a0les \u00a0otorga \u00a0el \u00a0art\u00edculo 318 del C\u00f3digo de Procedimiento Penal, contando \u00a0con \u00a0los \u00a0potenciales \u00a0testigos Carlos Javier Uma\u00f1a Pascuas y Gustavo Carrizosa \u00a0Penagos, \u00a0y \u00a0dentro del cual fue incluido H\u00c1ROLD IV\u00c1N GRANADA GARZ\u00d3N con base \u00a0en \u00a0la \u00a0\u201cinformaci\u00f3n \u00a0imprudente\u201d \u00a0de \u00a0su \u00a0prontuario criminal suministrada \u00a0mediante \u00a0el oficio policivo del 13 de abril de 2002, acto con el cual se busc\u00f3 \u00a0individualizar \u00a0al \u00a0conductor \u00a0de la motocicleta utilizada en el asalto pero que \u00a0se \u00a0cumpli\u00f3 \u00a0sin \u00a0atender \u00a0las \u00a0exigencias \u00a0se\u00f1aladas \u00a0en el art\u00edculo 304 del \u00a0C\u00f3digo \u00a0de Procedimiento Penal, como quiera que no intervino ni la Fiscal\u00eda ni \u00a0el Ministerio P\u00fablico. \u00a0\u00a0<\/p>\n<p>Adicionalmente demerita los resultados de tal \u00a0actividad \u00a0investigativa en cuanto afect\u00f3 la imparcialidad de la posteriormente \u00a0realizada \u00a0por \u00a0el \u00a0\u00f3rgano \u00a0instructor \u00a0el \u00a019 de los citados mes y a\u00f1o con la \u00a0participaci\u00f3n \u00a0de todos los sujetos procesales, falta de objetividad en la cual \u00a0asegura \u00a0 tambi\u00e9n \u00a0incidieron \u00a0las \u00a0publicaciones \u00a0en \u00a0los \u00a0medios \u00a0masivos \u00a0de \u00a0comunicaci\u00f3n \u00a0de \u00a0las \u00a0ruedas \u00a0de \u00a0prensa en que particip\u00f3 GRANADA GARZ\u00d3N dos \u00a0d\u00edas \u00a0despu\u00e9s \u00a0de \u00a0su \u00a0aprehensi\u00f3n, \u00a0y \u00a0de \u00a0su \u00a0fotograf\u00eda, el 17 de mayo de \u00a02002. \u00a0\u00a0<\/p>\n<p>Tales \u00a0irregularidades \u00a0indujeron \u00a0al \u00a0juez \u00a0plural \u00a0en \u00a0error \u00a0por \u00a0falso \u00a0juicio \u00a0de \u00a0legalidad \u00a0reca\u00eddo \u00a0sobre \u00a0el primer \u00a0reconocimiento fotogr\u00e1fico. \u00a0\u00a0<\/p>\n<p>Con el fin de desvirtuar el m\u00e9rito otorgado \u00a0al \u00a0citado \u00a0acto, \u00a0destaca \u00a0la imposibilidad en que se encontr\u00f3 tanto la esposa \u00a0del \u00a0occiso \u00a0como \u00a0el \u00a0administrador del parqueadero en donde fue descubierta la \u00a0motocicleta \u00a0de \u00a0autos, \u00a0de \u00a0reconocer \u00a0a \u00a0H\u00c1ROLD \u00a0IV\u00c1N \u00a0GRANADA \u00a0GARZ\u00d3N como \u00a0protagonista del episodio criminal. \u00a0\u00a0<\/p>\n<p>La anulaci\u00f3n de la actuaci\u00f3n por el motivo \u00a0comentado \u00a0la \u00a0solicita \u00a0el \u00a0demandante a partir de la resoluci\u00f3n de cierre del \u00a0ciclo instructivo. \u00a0\u00a0<\/p>\n<p>Tercer ataque: \u00a0<\/p>\n<p>En \u00a0forma \u00a0subsidiaria acusa la sentencia de \u00a0violaci\u00f3n \u00a0directa \u00a0de la ley sustancial por indebida aplicaci\u00f3n del art\u00edculo \u00a07\u00b0 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, que autoriza al juzgador a resolver \u00a0toda duda a favor del procesado. \u00a0\u00a0<\/p>\n<p>Al sustentar este cargo el demandante destaca \u00a0los \u00a0siguientes \u00a0aspectos \u00a0probatorios: \u00a0la \u00a0ausencia \u00a0en poder de H\u00c1ROLD IV\u00c1N \u00a0GRANADA \u00a0GARZ\u00d3N, \u00a0al \u00a0momento \u00a0de \u00a0la \u00a0captura, \u00a0de \u00a0objetos indicativos de que \u00a0hubiera \u00a0participado \u00a0en \u00a0los \u00a0delitos \u00a0investigados, \u00a0pues \u00a0no \u00a0llevaba consigo \u00a0cuantiosas \u00a0sumas \u00a0de \u00a0dinero, armas de fuego, llaves o casco de motocicleta, y, \u00a0adem\u00e1s, \u00a0durante \u00a0el \u00a0allanamiento \u00a0a \u00a0su vivienda la fiscal\u00eda estableci\u00f3 las \u00a0circunstancias \u00a0precarias \u00a0habitacionales. \u00a0De \u00a0otra parte, logr\u00f3 demostrar que \u00a0habitualmente \u00a0permanece \u00a0laborando \u00a0en \u00a0un taller de zapater\u00eda sin que resulte \u00a0id\u00f3neo \u00a0para \u00a0desvirtuar \u00a0tal hecho suponer que durante el lapso delictual pudo \u00a0haber \u00a0abandonado \u00a0dicho \u00a0lugar \u00a0por \u00a0haberle sido concedido un permiso o con la \u00a0disculpa \u00a0de tener que comprar alg\u00fan material, pues al fin y al cabo ninguno de \u00a0estos dos eventos se prob\u00f3. \u00a0\u00a0<\/p>\n<p>El \u00a0descubrimiento \u00a0en \u00a0poder del acusado de \u00a0unas \u00a0prendas \u00a0que \u00a0no \u00a0coinciden \u00a0con las que vest\u00eda el hombre que accion\u00f3 el \u00a0arma \u00a0de \u00a0fuego \u00a0utilizada \u00a0para \u00a0acabar \u00a0con \u00a0la \u00a0existencia \u00a0de \u00a0Pedro Antonio \u00a0Mart\u00ednez \u00a0Galindo \u00a0y de un trozo de papel con el n\u00famero de radicaci\u00f3n de este \u00a0proceso, \u00a0elemento \u00a0\u00e9ste \u00a0que \u00a0no \u00a0fue sometido a un an\u00e1lisis grafol\u00f3gico que \u00a0permitiera \u00a0radicar \u00a0en \u00a0GRANADA \u00a0GARZ\u00d3N \u00a0la \u00a0autor\u00eda \u00a0de los grafismos en \u00e9l \u00a0consignados, \u00a0antes \u00a0que \u00a0infundir \u00a0certeza demuestran la existencia de una duda \u00a0razonable \u00a0que \u00a0debe ser resuelta mediante el dictado de sentencia absolutoria a \u00a0tono con la norma procesal inicialmente invocada. \u00a0\u00a0<\/p>\n<p>Cuarta tacha: \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Con \u00a0fundamento \u00a0en \u00a0la causal primera, cuerpo segundo del art\u00edculo \u00a0207 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento Penal acusa tambi\u00e9n la sentencia recurrida \u00a0\u201c&#8230;por \u00a0 \u00a0 contener \u00a0 \u00a0 falsos \u00a0 \u00a0 juicios&#8230;\u201d \u00a0 \u00a0 de \u00a0 \u00a0 las \u00a0 \u00a0siguientes \u00a0modalidades: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>a. De \u00a0 existencia \u00a0 en \u00a0 la \u00a0 construcci\u00f3n \u00a0 de \u00a0 los \u00a0 indicios \u00a0 de \u00a0\u201cpresencia\u201d, \u00a0 de \u00a0 \u201coportunidad\u201d, \u00a0\u201cde \u00a0huellas \u00a0materiales\u201d \u00a0y \u00a0de \u00a0\u201crelaci\u00f3n con los autores del homicidio\u201d. \u00a0 \u00a0\u00a0<\/p>\n<p>Desarrolla, \u00a0en su orden, este planteamiento \u00a0diciendo \u00a0que \u00a0la \u00a0incorporaci\u00f3n \u00a0ilegal \u00a0y \u00a0m\u00faltiple \u00a0de \u00a0medios \u00a0probatorios \u00a0dirigidos \u00a0a \u00a0la \u00a0individualizaci\u00f3n \u00a0e \u00a0identificaci\u00f3n \u00a0del autor delictual no \u00a0condujo \u00a0claramente \u00a0hacia \u00a0H\u00c1ROLD \u00a0IV\u00c1N GRANADA GARZ\u00d3N; tampoco se demostr\u00f3 \u00a0que \u00a0\u00e9ste \u00a0hubiese \u00a0incrementado notoriamente su peculio como suele sucederle a \u00a0quienes \u00a0obtienen dinero en forma il\u00edcita; el hallazgo en poder del incriminado \u00a0de \u00a0un \u201cjean\u201d no conduce a inferir que por ser esta la prenda que vest\u00eda el \u00a0sujeto \u00a0que \u00a0atac\u00f3 \u00a0con \u00a0arma \u00a0de \u00a0fuego \u00a0a \u00a0la v\u00edctima hubiera sido \u00e9l quien \u00a0realiz\u00f3 \u00a0tal acci\u00f3n, pues se trata de una prenda de uso popular, aparte de que \u00a0no \u00a0le \u00a0fue \u00a0hallada \u00a0en \u00a0su \u00a0poder la chaqueta que se dice vest\u00eda el criminal; \u00a0tampoco \u00a0se \u00a0estableci\u00f3 \u00a0alg\u00fan \u00a0tipo \u00a0de \u00a0relaci\u00f3n \u00a0laboral, \u00a0de amistad o de \u00a0paisanaje \u00a0entre \u00a0el \u00a0inculpado \u00a0y \u00a0los \u00a0tenedores \u00a0de \u00a0la \u00a0motocicleta \u00a0que fue \u00a0abandonada e incautada. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>a. De \u00a0identidad, \u00a0derivado \u00a0de la tergiversaci\u00f3n que hizo el Tribunal \u00a0de \u00a0las \u00a0\u201cpruebas \u00a0referentes \u00a0a la exhibici\u00f3n previa por los funcionarios de \u00a0polic\u00eda \u00a0judicial \u00a0de los archivos delincuenciales\u201d, enunciado que se abstuvo \u00a0de desarrollar. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>a. Y, \u00a0 de \u00a0 falso \u00a0raciocinio \u00a0en \u00a0la \u00a0deducci\u00f3n \u00a0del \u00a0indicio \u00a0\u201cde \u00a0conocimiento previo con los autores del homicidio\u201d. \u00a0 \u00a0\u00a0<\/p>\n<p>Explic\u00f3 \u00a0 esta \u00a0 idea \u00a0 contrastando \u00a0los \u00a0testimonios \u00a0de \u00a0Carlos \u00a0Javier \u00a0Uma\u00f1a \u00a0Pascuas y de Gustavo Carrizosa Penagos, \u00a0quienes \u00a0reconocieron \u00a0a \u00a0su \u00a0procurado \u00a0como \u00a0el \u00a0parrillero \u00a0de la motocicleta \u00a0utilizada \u00a0para \u00a0interceptar el veh\u00edculo en el que se movilizaba el occiso, con \u00a0las \u00a0declaraciones \u00a0de \u00a0Gloria \u00a0Mar\u00eda \u00a0Rinc\u00f3n \u00a0y \u00a0Hugo de Jes\u00fas Daza Aguilar, \u00a0quienes \u00a0 guardaron \u00a0 silencio \u00a0 sobre \u00a0 tal \u00a0 evento, \u00a0pruebas \u00a0\u00e9stas \u00a0que \u00a0se \u00a0desconocieron \u00a0para \u00a0concluir \u00a0de manera err\u00f3nea la existencia de certeza en la \u00a0imputaci\u00f3n \u00a0de \u00a0coautor\u00eda \u00a0penal, \u00a0transgrediendo de esta manera las normas de \u00a0derecho sustancial invocadas al inicio de la demanda. \u00a0\u00a0<\/p>\n<p>Al \u00a0concluir \u00a0su \u00a0disertaci\u00f3n \u00a0el libelista \u00a0pidi\u00f3 \u00a0casar \u00a0la \u00a0sentencia \u00a0impugnada, \u00a0y, en su lugar, absolver H\u00c1ROLD IV\u00c1N \u00a0GRANADA \u00a0 GARZ\u00d3N \u00a0 de \u00a0los \u00a0cargos \u00a0por \u00a0los \u00a0cuales \u00a0fue \u00a0convocado \u00a0a \u00a0juicio \u00a0criminal. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES\u00a0 \u00a0 DE\u00a0 \u00a0LA\u00a0 \u00a0CORTE: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a01. \u00a0 \u00a0 \u00a0 \u00a0La \u00a0casaci\u00f3n \u00a0es \u00a0un \u00a0medio \u00a0extraordinario \u00a0de impugnaci\u00f3n y, por \u00a0tanto, \u00a0no \u00a0constituye \u00a0sede \u00a0adicional \u00a0para \u00a0prolongar \u00a0el \u00a0debate \u00a0probatorio \u00a0cumplido \u00a0en \u00a0las \u00a0instancias \u00a0ordinarias \u00a0y \u00a0concluido \u00a0con el fallo de segundo \u00a0grado; \u00a0por \u00a0el \u00a0contrario, \u00a0la admisi\u00f3n de la demanda exige el cumplimiento de \u00a0espec\u00edficos \u00a0requisitos \u00a0formales orientados a demostrar a trav\u00e9s de un juicio \u00a0t\u00e9cnico \u00a0 \u00a0 jur\u00eddico \u00a0 \u00a0 que \u00a0 \u00a0 en \u00a0 \u00a0 dicha \u00a0 \u00a0 providencia \u00a0 \u00a0 -la \u00a0cual \u00a0arriba a esta sede amparada de \u00a0la \u00a0 \u00a0 \u00a0dual \u00a0 \u00a0 \u00a0presunci\u00f3n \u00a0 \u00a0 de \u00a0 \u00a0 acierto \u00a0 \u00a0 y \u00a0 \u00a0 legalidad-, \u00a0se incurri\u00f3 en errores de hecho o de \u00a0derecho \u00a0ostensibles \u00a0y \u00a0relevantes o se profiri\u00f3 en una causa viciada, eventos \u00a0que reclaman para s\u00ed el necesario correctivo. \u00a0\u00a0<\/p>\n<p>El \u00a0art\u00edculo 212 de la Ley 600 de 2000 fija \u00a0las \u00a0 reglas \u00a0 para \u00a0la \u00a0elaboraci\u00f3n \u00a0del \u00a0libelo \u00a0cuyo \u00a0cumplimiento \u00a0es\u00a0 \u00a0ineludible \u00a0 y \u00a0 cuando \u00a0 se \u00a0 soslaya \u00a0aqu\u00e9lla \u00a0relacionada \u00a0con \u00a0la \u00a0adecuada \u00a0formulaci\u00f3n \u00a0de \u00a0los \u00a0cargos \u00a0y \u00a0se \u00a0omite indicar con la claridad y precisi\u00f3n \u00a0debidas \u00a0 sus \u00a0 fundamentos, \u00a0 la \u00a0 consecuencia \u00a0 procesal \u00a0 inmediata \u00a0 es \u00a0la \u00a0inadmisi\u00f3n1. \u00a0\u00a0<\/p>\n<p>2. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Este marco conceptual permite afirmar que \u00a0si \u00a0bien \u00a0el censor acert\u00f3 en la demanda al identificar los sujetos procesales, \u00a0sintetizar \u00a0 los \u00a0 hechos \u00a0 juzgados, \u00a0relacionar \u00a0brevemente \u00a0los \u00a0antecedentes \u00a0procesales \u00a0y \u00a0al \u00a0se\u00f1alar \u00a0como causales la tercera y la primera, equivoc\u00f3 el \u00a0sendero \u00a0de la casaci\u00f3n al desarrollarlas pues no cumpli\u00f3 con los presupuestos \u00a0de \u00a0precisi\u00f3n y claridad requeridos para la demostraci\u00f3n de las censuras, como \u00a0se pasa a explicar: \u00a0\u00a0<\/p>\n<p>3. \u00a0Las \u00a0siguientes \u00a0son las falencias de la \u00a0demanda \u00a0que \u00a0impiden \u00a0tener por cumplida la exigencia referida a la indicaci\u00f3n \u00a0clara y precisa de los fundamentos de los cargos, a saber: \u00a0\u00a0<\/p>\n<p>3.1. Primer quebranto: \u00a0<\/p>\n<p>Su \u00a0formulaci\u00f3n \u00a0al \u00a0amparo \u00a0de \u00a0la \u00a0causal \u00a0tercera \u00a0de \u00a0casaci\u00f3n, \u00a0debe ce\u00f1irse a unas exigencias b\u00e1sicas que permitan a \u00a0la \u00a0Corte \u00a0abordar \u00a0el \u00a0estudio \u00a0t\u00e9cnico \u00a0y \u00a0jur\u00eddico \u00a0de \u00a0un \u00a0fallo \u00a0o de una \u00a0actuaci\u00f3n, \u00a0seg\u00fan \u00a0el caso, con un margen de movilidad relativo, de manera que \u00a0la \u00a0rigidez \u00a0formal \u00a0no haga nugatoria la posibilidad de reajustar la estructura \u00a0del \u00a0proceso \u00a0o \u00a0la \u00a0actividad de los funcionarios judiciales a la legalidad sin \u00a0que \u00a0este \u00a0medio \u00a0extraordinario \u00a0de \u00a0impugnaci\u00f3n \u00a0pierda \u00a0sus caracter\u00edsticas \u00a0esenciales y principalmente su finalidad. \u00a0\u00a0<\/p>\n<p>La \u00a0 jurisprudencia \u00a0 de \u00a0 la \u00a0Sala \u00a0tiene \u00a0establecido \u00a0que \u00a0trat\u00e1ndose \u00a0de \u00a0la \u00a0causal de nulidad por la trasgresi\u00f3n del \u00a0principio \u00a0de \u00a0investigaci\u00f3n \u00a0integral \u00a0no \u00a0resulta \u00a0suficiente \u00a0afirmar que se \u00a0omiti\u00f3 \u00a0la \u00a0pr\u00e1ctica \u00a0de \u00a0determinadas pruebas, como lo hizo el censor en este \u00a0caso \u00a0al \u00a0reclamar \u00a0el \u00a0arribo \u00a0del \u00a0historial de la motocicleta incautada en el \u00a0curso \u00a0de \u00a0esta actuaci\u00f3n y presuntamente utilizada por los autores delictuales \u00a0para \u00a0la \u00a0consumaci\u00f3n \u00a0del concurso m\u00faltiple de conductas que se le endilgan y \u00a0de \u00a0los \u00a0comparendos \u00a0elaborados por las autoridades de tr\u00e1nsito de Medell\u00edn e \u00a0Ibagu\u00e9 a quienes la condujeron por la \u00e9poca del insuceso. \u00a0\u00a0<\/p>\n<p>Tampoco \u00a0pod\u00eda \u00a0el \u00a0accionante \u00a0limitarse a \u00a0afirmar \u00a0que \u00a0en \u00a0este \u00a0asunto \u00a0se \u00a0requer\u00edan \u00a0otros elementos probatorios, sin \u00a0especificar \u00a0 cu\u00e1les, \u00a0para \u00a0conocer \u00a0las \u00a0personas \u00a0con \u00a0v\u00ednculos \u00a0con \u00a0dicho \u00a0automotor \u00a0durante \u00a0la \u00a0\u00e9poca \u00a0de los acontecimientos investigados, pues estaba \u00a0obligado \u00a0a acercarse al contenido material de las pruebas omitidas, y, adem\u00e1s, \u00a0a \u00a0demostrar \u00a0la \u00a0pertinencia, \u00a0conducencia \u00a0y \u00a0utilidad \u00a0de \u00a0dicho \u00a0material, y \u00a0especialmente, \u00a0su incidencia en el sentido de la sentencia final que, seg\u00fan lo \u00a0ha sostenido la Corte: \u00a0\u00a0<\/p>\n<p>\u201c&#8230;no \u00a0surge \u00a0del medio de convicci\u00f3n en \u00a0s\u00ed \u00a0mismo \u00a0considerado \u00a0sino de su confrontaci\u00f3n l\u00f3gica con las probanzas que \u00a0sustentaron \u00a0el fallo, de modo que aparezca que de haberse llevado a cabo, \u00e9ste \u00a0hubiera \u00a0sido \u00a0distinto \u00a0y favorable al procesado\u201d2. \u00a0\u00a0<\/p>\n<p>El \u00a0vac\u00edo \u00a0dejado por el incumplimiento de \u00a0las \u00a0 rese\u00f1adas \u00a0exigencias \u00a0impide \u00a0establecer \u00a0en \u00a0qu\u00e9 \u00a0grado \u00a0la \u00a0falta \u00a0de \u00a0aplicaci\u00f3n \u00a0del \u00a0principio de investigaci\u00f3n integral comprometi\u00f3 la garant\u00eda \u00a0fundamental \u00a0de \u00a0la defensa, luego el cargo as\u00ed formulado resulta inabordable y \u00a0conduce al rechazo del libelo que lo contiene. \u00a0\u00a0<\/p>\n<p>3.2. Segundo reparo: \u00a0<\/p>\n<p>Con fundamento en la causal 3\u00aa de casaci\u00f3n \u00a0pretende \u00a0el \u00a0libelista \u00a0que \u00a0se declare la nulidad de lo actuado por violaci\u00f3n \u00a0del \u00a0 derecho \u00a0 de \u00a0defensa, \u00a0a \u00a0partir \u00a0de \u00a0la \u00a0resoluci\u00f3n \u00a0que \u00a0clausur\u00f3 \u00a0la \u00a0instrucci\u00f3n, \u00a0en raz\u00f3n de haber sido vinculado a ella su representado con base \u00a0en \u00a0un \u00a0reconocimiento \u00a0fotogr\u00e1fico \u00a0realizado \u00a0por la Polic\u00eda Judicial sin la \u00a0presencia \u00a0de la Fiscal\u00eda y el Ministerio P\u00fablico en evidente trasgresi\u00f3n del \u00a0art\u00edculo \u00a0304 \u00a0del \u00a0C\u00f3digo \u00a0de \u00a0Procedimiento \u00a0Penal, \u00a0no \u00a0obstante haber sido \u00a0repetida \u00a0la \u00a0diligencia por el ente investigador competente, como quiera que la \u00a0imparcialidad \u00a0de \u00a0los \u00a0resultados \u00a0obtenidos \u00a0en \u00a0la \u00a0segunda diligencia se vio \u00a0afectada \u00a0por \u00a0la \u00a0anterior \u00a0y \u00a0por las publicaciones de prensa relacionadas con \u00a0H\u00c1ROLD IV\u00c1N GRANADA GARZ\u00d3N. \u00a0\u00a0<\/p>\n<p>Faltando \u00a0a \u00a0los \u00a0requisitos \u00a0de claridad y \u00a0precisi\u00f3n \u00a0el \u00a0demandante \u00a0mezcl\u00f3 \u00a0antit\u00e9cnicamente \u00a0para efectos del recurso \u00a0extraordinario \u00a0las \u00a0conculcaciones \u00a0al \u00a0debido \u00a0proceso y al derecho de defensa \u00a0toda \u00a0 vez \u00a0 que \u00a0 su \u00a0 adecuada \u00a0formulaci\u00f3n \u00a0obliga \u00a0a \u00a0plantearlas \u00a0de \u00a0modo \u00a0independiente \u00a0por cuanto la naturaleza diversa de dichas prerrogativas conlleva \u00a0diferencia \u00a0tambi\u00e9n \u00a0en \u00a0su \u00a0demostraci\u00f3n y consecuencias, pues mientras aquel \u00a0concierne \u00a0a la estructura misma del proceso \u00e9sta hace relaci\u00f3n a un garant\u00eda \u00a0de los sujetos procesales. \u00a0\u00a0<\/p>\n<p>El casacionista orienta el reproche hacia la \u00a0nulidad \u00a0del reconocimiento fotogr\u00e1fico realizado por la Polic\u00eda Judicial, sin \u00a0embargo \u00a0pide la imposici\u00f3n de tal sanci\u00f3n procesal a partir de la resoluci\u00f3n \u00a0de \u00a0cierre \u00a0de \u00a0la \u00a0investigaci\u00f3n, \u00a0sin \u00a0tener en cuenta que el vicio solamente \u00a0afectar\u00eda el elemento probatorio m\u00e1s no la actuaci\u00f3n. \u00a0\u00a0<\/p>\n<p>Pero \u00a0como \u00a0en \u00a0realidad dirigi\u00f3 el ataque \u00a0hacia \u00a0la \u00a0legalidad \u00a0del \u00a0mencionado \u00a0reconocimiento \u00a0fotogr\u00e1fico -no \u00a0obstante \u00a0admitir \u00a0t\u00e1citamente \u00a0la \u00a0existencia \u00a0 \u00a0 de \u00a0 \u00a0 otro, \u00a0 \u00a0 practicado \u00a0 \u00a0 en \u00a0 \u00a0debida \u00a0 \u00a0forma-, \u00a0en tal caso le correspond\u00eda formular \u00a0el \u00a0cargo \u00a0por violaci\u00f3n indirecta de la ley sustancial determinada por errores \u00a0de \u00a0 derecho \u00a0 por \u00a0 falso \u00a0 juicio \u00a0 de \u00a0legalidad3 \u00a0 \u00a0y \u00a0 acreditar \u00a0 que \u00a0 los \u00a0sentenciadores \u00a0otorgaron cr\u00e9dito en su decisi\u00f3n a un medio de prueba aportado \u00a0al \u00a0 proceso \u00a0de \u00a0manera \u00a0irregular \u00a0por \u00a0desconocimiento \u00a0de \u00a0los \u00a0presupuestos \u00a0establecidos \u00a0por \u00a0la \u00a0ley \u00a0para su producci\u00f3n y acopio, adicionalmente, deb\u00eda \u00a0establecer \u00a0cu\u00e1l \u00a0fue \u00a0su trascendencia en el sentido del fallo y demostrar que \u00a0al \u00a0ser \u00a0marginado, \u00a0aquellas \u00a0pruebas \u00a0libres \u00a0de \u00a0tacha, \u00a0conducen \u00a0a \u00a0que las \u00a0conclusiones de la sentencia sean sustancialmente diferentes. \u00a0\u00a0<\/p>\n<p>Adem\u00e1s, la cr\u00edtica que hizo el demandante \u00a0al \u00a0valor \u00a0otorgado por los juzgadores de instancia al mencionado reconocimiento \u00a0y \u00a0al \u00a0desconocimiento \u00a0de \u00a0la imposibilidad en que se encontr\u00f3 tanto la esposa \u00a0del \u00a0occiso \u00a0de individualizar al conductor de la motocicleta incautada, como el \u00a0administrador \u00a0del parqueadero en donde fue incautada, de identificar a quien la \u00a0llev\u00f3 \u00a0a dicho lugar, antes que corresponderle al libelista atacar la legalidad \u00a0de \u00a0dicho \u00a0elemento, le implicaba abordar la discusi\u00f3n dentro de la perspectiva \u00a0t\u00e9cnica \u00a0del error de hecho derivado de falso raciocinio que se presenta cuando \u00a0de \u00a0un \u00a0elemento \u00a0de \u00a0convicci\u00f3n \u00a0se \u00a0derivan conclusiones en contrav\u00eda de los \u00a0principios \u00a0de \u00a0la \u00a0sana \u00a0cr\u00edtica, \u00a0esto \u00a0es, los postulados de la l\u00f3gica, las \u00a0leyes de la ciencia o las reglas de experiencia. \u00a0\u00a0<\/p>\n<p>Con \u00a0 argumentaci\u00f3n \u00a0tan \u00a0contradictoria \u00a0imposible \u00a0le \u00a0resulta \u00a0a \u00a0la \u00a0Sala \u00a0establecer \u00a0cu\u00e1l \u00a0es \u00a0en \u00a0verdad \u00a0el error \u00a0denunciado y, en consecuencia, examinar la censura. \u00a0\u00a0<\/p>\n<p>3.3. Tercera tacha: \u00a0<\/p>\n<p>La \u00a0violaci\u00f3n directa de la ley sustancial \u00a0por \u00a0indebida \u00a0aplicaci\u00f3n del art\u00edculo 7\u00b0 del C\u00f3digo de Procedimiento Penal, \u00a0contentivo \u00a0 del \u00a0 apotegma \u00a0 del \u00a0 in \u00a0 dubio \u00a0 pro \u00a0reo, \u00a0seg\u00fan \u00a0reiterado \u00a0criterio \u00a0de \u00a0esta Sala, debe \u00a0emprenderse as\u00ed \u00a0\u00a0<\/p>\n<p>\u201cFrente a este planteamiento el recurrente \u00a0olvid\u00f3 \u00a0que \u00a0cuando la pretensi\u00f3n del casacionista se dirija al reconocimiento \u00a0del \u00a0in \u00a0dubio \u00a0pro \u00a0reo, la \u00a0jurisprudencia \u00a0de \u00a0la Sala tiene entendido que dos son las alternativas con que \u00a0cuenta \u00a0para \u00a0su \u00a0reclamo \u00a0en \u00a0esta \u00a0sede: Una, acudiendo a los postulados de la \u00a0violaci\u00f3n \u00a0directa \u00a0cuando el fallador admite en la motivaci\u00f3n de la sentencia \u00a0su \u00a0ocurrencia \u00a0pero \u00a0no \u00a0la \u00a0reconoce \u00a0en la parte resolutiva; y otra, bajo los \u00a0lineamientos \u00a0de \u00a0la violaci\u00f3n indirecta en el evento\u00a0 en que la sentencia \u00a0no \u00a0la \u00a0admite \u00a0pero \u00a0el demandante demuestra a la Corte su existencia por haber \u00a0incurrido \u00a0aqu\u00e9l \u00a0en errores de derecho o hecho.\u201d4 \u00a0\u00a0<\/p>\n<p>Sin embargo, antes que sostener y demostrar \u00a0el \u00a0libelista \u00a0que \u00a0los juzgadores al valorar el caudal probatorio admitieron en \u00a0la \u00a0secci\u00f3n \u00a0motiva \u00a0de \u00a0sus \u00a0providencias \u00a0la existencia de duda, se dedic\u00f3 a \u00a0expresar \u00a0las razones de su discrepancia con dicha actividad y a criticarlos por \u00a0haber \u00a0desconocido \u00a0la \u00a0carencia \u00a0de \u00a0elementos \u00a0incriminatorios \u00a0en poder de su \u00a0representado \u00a0al \u00a0momento \u00a0de \u00a0la captura y las deplorables circunstancias de la \u00a0vivienda \u00a0ocupada \u00a0por \u00a0\u00e9ste, \u00a0a \u00a0su \u00a0juicio, \u00a0demostrativas \u00a0de la ausencia de \u00a0participaci\u00f3n \u00a0de su representado en el apoderamiento il\u00edcito de una cuantiosa \u00a0suma \u00a0de \u00a0dinero, \u00a0y, \u00a0por \u00a0haber \u00a0negado \u00a0valor \u00a0exculpatorio al hecho de haber \u00a0demostrado \u00a0H\u00c1ROLD \u00a0IV\u00c1N GRANADA GARZ\u00d3N su permanencia por la \u00e9poca de autos \u00a0en un taller de zapater\u00eda. \u00a0\u00a0<\/p>\n<p>Para \u00a0imprimirle \u00a0fuerza \u00a0al \u00a0planteamiento \u00a0argument\u00f3 \u00a0que \u00a0no \u00a0pod\u00edan inferir l\u00f3gicamente las instancias responsabilidad \u00a0penal \u00a0en \u00a0contra de H\u00c1ROLD IV\u00c1N GRANADA GARZ\u00d3N del hecho de haber encontrado \u00a0en \u00a0su \u00a0residencia \u00a0unas prendas de vestir similares a las usadas por uno de los \u00a0asaltantes, \u00a0pues \u00a0no \u00a0se \u00a0estableci\u00f3 \u00a0que \u00a0se tratara de las mismas, as\u00ed como \u00a0tampoco, \u00a0del \u00a0descubrimiento \u00a0en \u00a0poder \u00a0de \u00a0\u00e9ste de un trozo de papel con una \u00a0anotaci\u00f3n \u00a0del n\u00famero de radicaci\u00f3n de este proceso penal, sin que se hubiera \u00a0establecido plenamente que los grafismos proven\u00edan del acusado. \u00a0\u00a0<\/p>\n<p>Dicho \u00a0esfuerzo \u00a0argumentativo \u00a0se reduce a \u00a0controvertir \u00a0las \u00a0razones \u00a0aducidas \u00a0por \u00a0el \u00a0Tribunal \u00a0al \u00a0valorar el material \u00a0probatorio \u00a0recaudado \u00a0y \u00a0evidencia el total alejamiento del casacionista de las \u00a0pautas \u00a0fijadas \u00a0por \u00a0la Corte cuando se pretende el reconocimiento del in dubio \u00a0pro \u00a0reo \u00a0por \u00a0la \u00a0v\u00eda \u00a0de \u00a0la \u00a0violaci\u00f3n \u00a0directa de la ley sustancial, luego \u00a0entrabada \u00a0la discusi\u00f3n de este cargo se impone el rechazo de la demanda que lo \u00a0contiene. \u00a0\u00a0<\/p>\n<p>3.4. \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0Cuarto reproche: \u00a0\u00a0<\/p>\n<p>Invocando la causal primera, cuerpo segundo \u00a0del \u00a0art\u00edculo \u00a0207 del C\u00f3digo de Procedimiento Penal, el actor plantea que los \u00a0jueces \u00a0 de \u00a0instancia \u00a0incurrieron \u00a0en \u00a0\u201c&#8230;falsos \u00a0juicios&#8230;\u201d de existencia en la construcci\u00f3n de los \u00a0indicios \u00a0 \u201cde \u00a0 presencia\u201d, \u00a0 \u201cde \u00a0 oportunidad\u201d, \u00a0 \u201cde \u00a0las \u00a0huellas \u00a0materiales\u201d \u00a0y \u201cde relaci\u00f3n con los autores del homicidio\u201d; de identidad, \u00a0derivado \u00a0 de \u00a0la \u00a0tergiversaci\u00f3n \u00a0que \u00a0hizo \u00a0el \u00a0tribunal \u00a0de \u00a0las \u00a0\u201cpruebas \u00a0referentes \u00a0a la exhibici\u00f3n previa por los funcionarios de polic\u00eda judicial de \u00a0los \u00a0archivos \u00a0delincuenciales\u201d; \u00a0y, \u00a0de falso raciocinio en la deducci\u00f3n del \u00a0indicio \u201cde conocimiento previo de los autores del homicidio\u201d. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0Aunque \u00a0se presume que este ataque se postula al amparo de la causal \u00a0de \u00a0violaci\u00f3n \u00a0indirecta \u00a0de \u00a0la \u00a0ley \u00a0sustancial, \u00a0lo \u00a0cierto \u00a0es que al haber \u00a0incluido \u00a0 en \u00a0 \u00e9l \u00a0 tres \u00a0motivos \u00a0de \u00a0reproche \u00a0correspondientes \u00a0a \u00a0diversas \u00a0concepciones, \u00a0\u00e9stos \u00a0no \u00a0pod\u00edan \u00a0formularse \u00a0en la misma censura pues dada su \u00a0contradicci\u00f3n \u00a0 \u00a0y \u00a0 \u00a0autonom\u00eda \u00a0 \u00a0han \u00a0 \u00a0debido \u00a0 \u00a0proponerse \u00a0 \u00a0en \u00a0 \u00a0cargos \u00a0separados. \u00a0\u00a0<\/p>\n<p>La confusi\u00f3n antes destacada se extiende a \u00a0la \u00a0fundamentaci\u00f3n \u00a0del reproche, pues el casacionista no s\u00f3lo insisti\u00f3 en su \u00a0contrariedad \u00a0por \u00a0la \u00a0incorporaci\u00f3n \u00a0ilegal \u00a0y m\u00faltiple de medios probatorios \u00a0inculpatorios, \u00a0m\u00e1s \u00a0no \u00a0los especific\u00f3, sino que volvi\u00f3 sobre la ausencia de \u00a0prueba \u00a0de \u00a0hechos \u00a0negativos \u00a0indefinidos \u00a0y \u00a0reanud\u00f3 \u00a0sus divergencias por el \u00a0cr\u00e9dito \u00a0otorgado \u00a0a \u00a0los testimonios de Carlos Javier Uma\u00f1a Pascuas y Gustavo \u00a0Carrizosa \u00a0Penagos, \u00a0y \u00a0por el negado a los rendidos por Gloria Mar\u00eda Rinc\u00f3n y \u00a0Hugo de Jes\u00fas Daza Aguilar. \u00a0\u00a0<\/p>\n<p>Ignor\u00f3 \u00a0que \u00a0cuando \u00a0se \u00a0trata \u00a0de \u00a0falsos \u00a0juicios: \u00a0a) \u00a0de \u00a0existencia, \u00a0es necesario indicar cu\u00e1l fue el medio de prueba \u00a0omitido \u00a0o \u00a0supuesto, \u00a0cu\u00e1l la informaci\u00f3n objetivamente brindada y qu\u00e9 dej\u00f3 \u00a0de \u00a0 valorarse \u00a0 o \u00a0 qu\u00e9 \u00a0se \u00a0supuso, \u00a0as\u00ed \u00a0como \u00a0el \u00a0m\u00e9rito \u00a0demostrativo \u00a0a \u00a0asign\u00e1rsele; \u00a0b) \u00a0de identidad, es indispensable se\u00f1alar el contenido material \u00a0de \u00a0la prueba y c\u00f3mo la tergivers\u00f3, cercen\u00f3 o adicion\u00f3 el juzgador; y, c) de \u00a0raciocinio, \u00a0es \u00a0obligatorio \u00a0indicar en la valoraci\u00f3n individual o conjunta de \u00a0la \u00a0prueba cu\u00e1les fueron las reglas de la sana cr\u00edtica (principios de l\u00f3gica, \u00a0reglas \u00a0de \u00a0experiencia, \u00a0postulados de la ciencia) inapropiadamente aplicadas y \u00a0cu\u00e1l \u00a0debi\u00f3 \u00a0regular \u00a0dicha \u00a0labor. \u00a0Y, \u00a0en \u00a0todos los casos, reviste singular \u00a0importancia \u00a0 establecer \u00a0 la \u00a0repercusi\u00f3n \u00a0definitiva \u00a0del \u00a0desacierto \u00a0en \u00a0la \u00a0declaraci\u00f3n \u00a0de justicia contenida en la parte resolutiva del fallo5. \u00a0\u00a0<\/p>\n<p>La \u00a0recurrencia en el tema de los indicios, \u00a0le \u00a0exig\u00eda al demandante, a tono con las pautas t\u00e9cnicas fijadas por reiterada \u00a0jurisprudencia de esta Sala, la siguiente fundamentaci\u00f3n: \u00a0\u00a0<\/p>\n<p>\u201cSi el indicio es \u00a0un \u00a0medio \u00a0de \u00a0prueba, \u00a0debe \u00a0tenerse \u00a0claro que cuando se plantean en casaci\u00f3n \u00a0defectos \u00a0en \u00a0su \u00a0apreciaci\u00f3n \u00a0como \u00a0fundamento \u00a0de \u00a0la \u00a0violaci\u00f3n \u00a0de \u00a0la ley \u00a0sustancial, \u00a0la \u00a0v\u00eda \u00a0de \u00a0ataque \u00a0tiene \u00a0que ser la indirecta, siendo deber del \u00a0demandante \u00a0indicarle \u00a0a \u00a0la Corte la clase de error que denuncia (de hecho o de \u00a0derecho), \u00a0su \u00a0modalidad \u00a0y \u00a0si \u00a0lo predica del hecho indicador o probado, de la \u00a0inferencia \u00a0l\u00f3gica o de la fuerza persuasiva obtenida del an\u00e1lisis conjunto de \u00a0los \u00a0 \u00a0 \u00a0 \u00a0 \u00a0diferentes \u00a0 \u00a0 \u00a0 \u00a0 indicios.\u201d6 \u00a0\u00a0<\/p>\n<p>En ning\u00fan momento el recurrente se\u00f1al\u00f3 si \u00a0el \u00a0yerro atribuido a la decisi\u00f3n del Ad-quem \u00a0abarc\u00f3 \u00a0el hecho indicador, la inferencia l\u00f3gica o la fuerza \u00a0persuasiva \u00a0obtenida del an\u00e1lisis conjunto de los diferentes indicios, falta de \u00a0exactitud \u00a0\u00e9sta \u00a0que \u00a0imposibilita \u00a0el \u00a0an\u00e1lisis \u00a0formal \u00a0de \u00a0este \u00a0quebranto. \u00a0\u00a0<\/p>\n<p>4. \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0Las \u00a0m\u00faltiples \u00a0falencias \u00a0t\u00e9cnicas \u00a0y \u00a0desatinos \u00a0de \u00a0la \u00a0demanda \u00a0no pueden ser superadas ni corregidas por la Sala en \u00a0raz\u00f3n \u00a0del car\u00e1cter esencialmente rogado del recurso de casaci\u00f3n y por virtud \u00a0del \u00a0principio \u00a0de \u00a0limitaci\u00f3n \u00a0consagrado en el art\u00edculo 216 de la Ley 600 de \u00a02000, \u00a0luego \u00a0se \u00a0impone \u00a0su \u00a0inadmisi\u00f3n de conformidad con lo dispuesto por el \u00a0art\u00edculo 213 ib\u00eddem. \u00a0\u00a0<\/p>\n<p>5. \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0Finalmente, \u00a0ha \u00a0de precisarse que no se \u00a0vislumbra \u00a0dentro \u00a0de \u00a0la \u00a0actuaci\u00f3n \u00a0ni \u00a0en \u00a0el fallo impugnado, violaci\u00f3n de \u00a0derechos \u00a0o \u00a0garant\u00edas \u00a0del \u00a0acusado \u00a0que impongan el ejercicio de la casaci\u00f3n \u00a0oficiosa con el \u00fanico prop\u00f3sito de asegurar su protecci\u00f3n. \u00a0\u00a0<\/p>\n<p>A \u00a0m\u00e9rito de lo expuesto, la Corte Suprema \u00a0de Justicia, Sala de Casaci\u00f3n Penal, \u00a0\u00a0<\/p>\n<p>R E S U E L V E : \u00a0<\/p>\n<p>1. \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0INADMITIR \u00a0la \u00a0demanda \u00a0de casaci\u00f3n presentada en defensor del procesado H\u00c1ROLD IV\u00c1N GRANADA \u00a0GARZ\u00d3N \u00a0 y, \u00a0 en \u00a0consecuencia, \u00a0declarar \u00a0desierto \u00a0el \u00a0recurso \u00a0de \u00a0casaci\u00f3n \u00a0interpuesto. \u00a0\u00a0<\/p>\n<p>2. \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0ADVERTIR \u00a0que \u00a0contra esta providencia no procede ning\u00fan recurso. \u00a0\u00a0<\/p>\n<p>C\u00f3piese, \u00a0comun\u00edquese \u00a0y \u00a0devu\u00e9lvase \u00a0al \u00a0Tribunal de origen. \u00a0\u00a0<\/p>\n<p>C\u00daMPLASE. \u00a0<\/p>\n<p>MAURO SOLARTE PORTILLA \u00a0<\/p>\n<p>SIGIFREDO \u00a0 ESPINOSA \u00a0 P\u00c9REZ \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0ALFREDO \u00a0 \u00a0 \u00a0G\u00d3MEZ \u00a0QUINTERO \u00a0\u00a0<\/p>\n<p>Permiso \u00a0<\/p>\n<p>\u00c9DGAR \u00a0 LOMBANA \u00a0 TRUJILLO \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0 \u00c1LVARO O. P\u00c9REZ PINZ\u00d3N \u00a0\u00a0<\/p>\n<p>\u00a0 MARINA \u00a0 PULIDO \u00a0DE \u00a0BAR\u00d3N \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0JORGE \u00a0 \u00a0 \u00a0 L. \u00a0 \u00a0 \u00a0 QUINTERO \u00a0MILAN\u00c9S \u00a0\u00a0<\/p>\n<p>\u00a0 YESID RAM\u00cdREZ BASTIDAS \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 JAVIER ZAPATA ORTIZ \u00a0\u00a0<\/p>\n<p>TERESA RUIZ N\u00da\u00d1EZ \u00a0<\/p>\n<p>Secretaria. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0Auto \u00a0del 13 de julio de 2005, rad. 23.889. \u00a0\u00a0<\/p>\n<p>2 CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0Auto \u00a0del 17 de agosto de 2005, rad. N\u00b0 23.324. \u00a0\u00a0<\/p>\n<p>3 CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0Auto \u00a0del 30 de marzo de 2005, rad. N\u00b0 23.281. \u00a0\u00a0<\/p>\n<p>4 CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0Auto \u00a0del 17 de agosto de 2005, rad. N\u00b0 23.324. \u00a0\u00a0<\/p>\n<p>5 CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0Auto \u00a0del \u00a0 \u00a028 \u00a0 \u00a0de \u00a0 \u00a0abril \u00a0 \u00a0de \u00a0 \u00a02004, \u00a0 \u00a0rad. \u00a0 \u00a0N\u00b0 \u00a0 \u00a020.507; \u00a0 Sent. \u00a0del 26 de junio de 2002, rad. N\u00b0 \u00a011.451; \u00a0y \u00a0Auto del 29 de \u00a0enero de 2004, rad. 20.427. \u00a0\u00a0<\/p>\n<p>6 CORTE \u00a0SUPREMA \u00a0DE \u00a0JUSTICIA, \u00a0Auto \u00a0inadmite demanda del 18 de mayo de 2005, rad. N\u00b0 17.752. \u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 24913 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 Magistrado ponente: \u00a0 YESID \u00a0 \u00a0RAM\u00cdREZ \u00a0BASTIDAS \u00a0\u00a0 Aprobado \u00a0 Acta \u00a0 N\u00b0 \u00a0051 \u00a0\u00a0 Bogot\u00e1, \u00a0D. C., veinticinco (25) de mayo de \u00a0dos mil seis (2006). \u00a0\u00a0 V I S T O S \u00a0 Se procede a resolver [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-11370","post","type-post","status-publish","format-standard","hentry","category-14"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/11370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=11370"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/11370\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=11370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=11370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=11370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}