{"id":10052,"date":"2023-09-08T18:26:09","date_gmt":"2023-09-08T18:26:09","guid":{"rendered":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2327318-05-05\/"},"modified":"2023-09-08T18:26:09","modified_gmt":"2023-09-08T18:26:09","slug":"2327318-05-05","status":"publish","type":"post","link":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/2023\/09\/08\/2327318-05-05\/","title":{"rendered":"23273(18-05-05)"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Proceso No 23273 \u00a0<\/p>\n<p>CORTE SUPREMA DE JUSTICIA \u00a0<\/p>\n<p>SALA DE CASACI\u00d3N PENAL \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Magistrado \u00a0Ponente: \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0Dr. \u00a0ALFREDO \u00a0G\u00d3MEZ \u00a0QUINTERO \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0Aprobado Acta \u00a0No. 039 \u00a0\u00a0<\/p>\n<p>Bogot\u00e1, \u00a0D.C., dieciocho (18) de mayo de dos \u00a0mil cinco (2.005). \u00a0\u00a0<\/p>\n<p>VISTOS: \u00a0<\/p>\n<p>La Sala se pronuncia sobre la viabilidad de la \u00a0demanda \u00a0sustento \u00a0del \u00a0recurso \u00a0de \u00a0casaci\u00f3n \u00a0instaurado \u00a0por el apoderado del \u00a0procesado \u00a0EURIPIDES \u00a0ARCESIO ACEVEDO CARO, \u00a0contra \u00a0la sentencia proferida el 10 de septiembre de 2004 por el \u00a0Tribunal \u00a0Superior \u00a0de \u00a0Tunja \u00a0mediante \u00a0la \u00a0cual \u00a0confirm\u00f3 la dictada el 12 de \u00a0noviembre \u00a0de \u00a02003 \u00a0por el Juzgado Penal del Circuito de Garagoa (Boyac\u00e1), que \u00a0lo \u00a0conden\u00f3 \u00a0a \u00a0la pena de trescientos cuarenta y cinco (345) meses de prisi\u00f3n \u00a0por \u00a0 \u00a0hallarlo \u00a0 \u00a0responsable \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 conducta \u00a0 punible \u00a0 de \u00a0 homicidio \u00a0agravado. \u00a0\u00a0<\/p>\n<p>LOS HECHOS: \u00a0<\/p>\n<p>El \u00a025 \u00a0de \u00a0noviembre \u00a0de \u00a02002 \u00a0\u2013alrededor \u00a0 del \u00a0mediod\u00eda- \u00a0EURIPIDES \u00a0ARCESIO \u00a0ACEVEDO \u00a0CARO \u00a0regres\u00f3 \u00a0a \u00a0su casa rural ubicada en la vereda Fusa del \u00a0municipio \u00a0de \u00a0Chinavita \u00a0y \u00a0con \u00a0arma \u00a0blanca \u00a0dio muerte a su esposa Rosalbina \u00a0L\u00f3pez. \u00a0\u00a0<\/p>\n<p>FUNDAMENTOS DE LA IMPUGNACI\u00d3N: \u00a0<\/p>\n<p>Con \u00a0sustento \u00a0en \u00a0la \u00a0causal \u00a0primera \u00a0del \u00a0art\u00edculo \u00a0 207 \u00a0 de \u00a0 la \u00a0 ley \u00a0 600 \u00a0de \u00a02000 \u00a0se \u00a0postula \u00a0como \u00a0primer \u00a0cargo, la violaci\u00f3n directa de la \u00a0norma \u00a0de \u00a0derecho \u00a0sustancial \u00a0por \u00a0falta \u00a0de \u00a0aplicaci\u00f3n del art\u00edculo 57 del \u00a0c\u00f3digo penal consagratorio de la ira o intenso dolor. \u00a0\u00a0<\/p>\n<p>El recurrente se\u00f1ala que el tribunal olvid\u00f3 \u00a0que \u00a0la \u00a0prueba \u00a0testimonial permit\u00eda inferir que el procesado act\u00fao impulsado \u00a0por \u00a0la \u00a0ira, estado emocional que procede a conceptualizar para enseguida citar \u00a0las \u00a0declaraciones \u00a0de \u00a0Jorge \u00a0Pa\u00e9z \u00a0Rom\u00e1n, Oswaldo Antonio Roa Acevedo, Angel \u00a0Dios \u00a0 Hastamorir, \u00a0 Adanael \u00a0 Acevedo \u00a0 L\u00f3pez \u00a0 y \u00a0Mar\u00eda \u00a0Dioselina \u00a0Acevedo, \u00a0reproduciendo \u00a0los \u00a0apartes \u00a0de algunas de ellas en los que era posible entrever \u00a0la \u00a0 degradante \u00a0 o \u00a0 comentando \u00a0 su \u00a0 existencia \u00a0 a \u00a0partir \u00a0de \u00a0sus \u00a0propias \u00a0reflexiones. \u00a0\u00a0<\/p>\n<p>Advierte que la discusi\u00f3n gir\u00f3 en torno a la \u00a0imputabilidad \u00a0o \u00a0no \u00a0del \u00a0inculpado cuando era evidente que el inculpado hab\u00eda \u00a0obrado \u00a0bajo \u00a0el influjo de ese sentimiento, estado que no valor\u00f3 el fallador a \u00a0pesar de su notoriedad. \u00a0\u00a0<\/p>\n<p>Posteriormente \u00a0el \u00a0censor \u00a0afirma \u00a0que en lo \u00a0f\u00e1ctico \u00a0est\u00e1 \u00a0demostrado \u00a0que \u00a0la \u00a0persona con antecedentes de epilepsia debe \u00a0durante \u00a0toda \u00a0su vida consumir epamin y que su comportamiento no es igual al de \u00a0un \u00a0individuo normal aun cuando no sea considerada inimputable, en tanto que los \u00a0testigos se\u00f1alan que obr\u00f3 impulsado por la ira. \u00a0\u00a0<\/p>\n<p>Finalmente \u00a0critica \u00a0la clasificaci\u00f3n que se \u00a0hace \u00a0en la sentencia de las crisis epil\u00e9pticas, transcribe el p\u00e1rrafo de ella \u00a0en \u00a0que con sustento en la prueba testimonial se descarta que el acusado hubiera \u00a0actuado \u00a0bajo \u00a0un \u00a0episodio \u00a0de esas caracter\u00edsticas, para asentir el estado de \u00a0imputabilidad \u00a0que \u00a0se \u00a0da por probado y advertir que reprocha lo que se deja de \u00a0valorar: la ira. \u00a0\u00a0<\/p>\n<p>CONSIDERACIONES: \u00a0<\/p>\n<p>El \u00a0primer \u00a0cargo \u00a0de \u00a0la \u00a0demanda \u00a0no \u00a0cumple \u00a0con los requerimientos de \u00a0t\u00e9cnica \u00a0que \u00a0se tienen establecidos cuando se postula la violaci\u00f3n directa de \u00a0la \u00a0 ley, \u00a0 puesto \u00a0 que \u00a0 el \u00a0censor \u00a0en \u00a0abierta \u00a0contradicci\u00f3n \u00a0a \u00a0lo \u00a0dicho \u00a0invariablemente \u00a0acerca de la manera como debe desarrollarse el reparo, pretende \u00a0la \u00a0demostraci\u00f3n \u00a0del \u00a0error denunciado a trav\u00e9s de la prueba y de lo que ella \u00a0permit\u00eda concluir. \u00a0\u00a0<\/p>\n<p>Cuando \u00a0se \u00a0selecciona \u00a0la \u00a0causal primera de \u00a0casaci\u00f3n \u00a0cuerpo \u00a0primero, el actor admite los hechos en la forma en que se dan \u00a0por \u00a0probados \u00a0en \u00a0la \u00a0sentencia \u00a0y \u00a0la \u00a0apreciaci\u00f3n \u00a0de la prueba hecha por el \u00a0juzgador, \u00a0puesto \u00a0que la naturaleza del quebranto reprochado es la de juicio en \u00a0puro derecho. \u00a0\u00a0<\/p>\n<p>De modo que una vez identificado el sentido de \u00a0la \u00a0 violaci\u00f3n \u00a0directa \u00a0de \u00a0la \u00a0ley \u00a0\u2013falta \u00a0 de \u00a0 aplicaci\u00f3n, \u00a0aplicaci\u00f3n \u00a0indebida \u00a0o \u00a0interpretaci\u00f3n \u00a0err\u00f3nea- \u00a0el recurrente est\u00e1 obligado a proponer el debate en derecho, en cuyo \u00a0evento \u00a0le \u00a0resulta \u00a0imprescindible \u00a0adelantarlo \u00a0a \u00a0trav\u00e9s de una proposici\u00f3n \u00a0jur\u00eddica \u00a0completa \u00a0que le permita demostrar el error, la manera como se lleg\u00f3 \u00a0a \u00a0\u00e9l y la incidencia del mismo en la sentencia que haga necesario su reemplazo \u00a0para enmendarlo. \u00a0\u00a0<\/p>\n<p>Sin embargo, el demandante incumpli\u00f3 con sus \u00a0obligaciones \u00a0en \u00a0el \u00a0desarrollo \u00a0de \u00a0la \u00a0censura, \u00a0cuando \u00a0encamina \u00a0la misma a \u00a0advertir \u00a0que el fallador omiti\u00f3 apreciar lo que la prueba ense\u00f1aba, ya que en \u00a0su \u00a0criterio \u00a0la \u00a0misma permit\u00eda inferir que el procesado obr\u00f3 bajo el influjo \u00a0del estado emocional de la ira. \u00a0\u00a0<\/p>\n<p>Desde esa perspectiva la falta de aplicaci\u00f3n \u00a0de \u00a0la ley se origina en la violaci\u00f3n indirecta de la ley sustancial, en cuanto \u00a0a \u00a0ella \u00a0se \u00a0arriba \u00a0por \u00a0la \u00a0indebida \u00a0valoraci\u00f3n \u00a0de la prueba que hiciera el \u00a0juzgador, \u00a0lo \u00a0cual \u00a0significa \u00a0que \u00a0el \u00a0actor \u00a0no acepta los hechos como fueron \u00a0probados \u00a0 en \u00a0la \u00a0sentencia \u00a0ni \u00a0tampoco \u00a0la \u00a0apreciaci\u00f3n \u00a0de \u00a0los \u00a0medios \u00a0de \u00a0convicci\u00f3n, \u00a0ya \u00a0que \u00a0la \u00a0estima \u00a0parcial \u00a0por no haberse considerado el estado \u00a0emocional en que obr\u00f3 el procesado y que era reflejado por ella. \u00a0\u00a0<\/p>\n<p>Luego se le impon\u00eda acudir al cuerpo segundo \u00a0de \u00a0la \u00a0misma causal si lo que pretend\u00eda era discutir el contenido y el alcance \u00a0otorgado \u00a0en la sentencia por el fallador a la prueba testimonial relacionada en \u00a0la \u00a0demanda, \u00a0postulando \u00a0el \u00a0error \u00a0de \u00a0hecho \u00a0en cualquiera de sus modalidades \u00a0\u2013falsos \u00a0 juicios \u00a0 de \u00a0existencia \u00a0y \u00a0de \u00a0identidad o falso raciocinio-, pues las cr\u00edticas aducidas no \u00a0tienen \u00a0que ver con la legalidad en la aducci\u00f3n o en la pr\u00e1ctica de los medios \u00a0probatorios. \u00a0\u00a0<\/p>\n<p>La \u00a0Sala \u00a0ante \u00a0las \u00a0falencias \u00a0de \u00a0t\u00e9cnica \u00a0anotadas \u00a0al \u00a0cargo primero de la demanda lo inadmitir\u00e1, pues no puede entrar a \u00a0subsanarlas, \u00a0corregirlas \u00a0o \u00a0enmendarlas en virtud del principio de limitaci\u00f3n \u00a0\u2013art\u00edculo \u00a0216 \u00a0de la ley \u00a0600 \u00a0 \u00a0de \u00a0 \u00a02000- \u00a0 \u00a0y \u00a0 de \u00a0 la \u00a0 naturaleza \u00a0 rogada \u00a0 de \u00a0 la \u00a0 impugnaci\u00f3n \u00a0extraordinaria. \u00a0\u00a0<\/p>\n<p>Se \u00a0proceder\u00e1 a declarar ajustado el segundo \u00a0cargo \u00a0de la misma, por lo cual con fundamento en el art\u00edculo 213 de la ley 600 \u00a0de \u00a02000 se dispone correr traslado del mismo al Procurador Delegado en lo Penal \u00a0por \u00a0el \u00a0t\u00e9rmino \u00a0de veinte (20) d\u00edas, para que emita el concepto de rigor que \u00a0corresponda. \u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la CORTE SUPREMA DE \u00a0JUSTICIA, Sala de Casaci\u00f3n Penal, \u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>1. Inadmitir el primer cargo de la demanda de \u00a0casaci\u00f3n \u00a0presentada \u00a0por el apoderado judicial del procesado EURIPIDES ARCESIO \u00a0ACEVEDO CARO. \u00a0\u00a0<\/p>\n<p>2. \u00a0Declarar \u00a0ajustado el cargo segundo de la \u00a0demanda \u00a0de \u00a0casaci\u00f3n \u00a0citada. \u00a0En \u00a0consecuencia, se dispone correr traslado de \u00a0ella \u00a0al \u00a0Procurador \u00a0Delegado \u00a0en lo Penal por el t\u00e9rmino de veinte (20) d\u00edas \u00a0para lo de su cargo. \u00a0\u00a0<\/p>\n<p>3. \u00a0Contra \u00a0esta decisi\u00f3n no procede recurso \u00a0alguno. \u00a0\u00a0<\/p>\n<p>C\u00f3piese y C\u00famplase. \u00a0<\/p>\n<p>MARINA PULIDO DE BAR\u00d3N \u00a0<\/p>\n<p>SIGIFREDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0ESPINOSA \u00a0P\u00c9REZ\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0HERMAN \u00a0 \u00a0GAL\u00c1N \u00a0CASTELLANOS \u00a0\u00a0<\/p>\n<p>ALFREDO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0G\u00d3MEZ \u00a0QUINTERO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0EDGAR LOMBANA TRUJILLO\u00a0\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>\u00c1LVARO \u00a0ORLANDO \u00a0P\u00c9REZ \u00a0PINZ\u00d3N\u00a0 JORGE \u00a0LUIS \u00a0 QUINTERO \u00a0 MILAN\u00c9S \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>YESID \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0RAM\u00cdREZ \u00a0BASTIDAS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0MAURO SOLARTE PORTILLA \u00a0\u00a0<\/p>\n<p>Teresa Ruiz N\u00fa\u00f1ez \u00a0<\/p>\n<p>Secretaria \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Proceso No 23273 \u00a0 CORTE SUPREMA DE JUSTICIA \u00a0 SALA DE CASACI\u00d3N PENAL \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0Magistrado \u00a0Ponente: \u00a0\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-10052","post","type-post","status-publish","format-standard","hentry","category-13"],"_links":{"self":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/10052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/comments?post=10052"}],"version-history":[{"count":0,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/posts\/10052\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/media?parent=10052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/categories?post=10052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmsjuridica.com\/buscador_20179478954\/salapenalcronologico20230723\/wp-json\/wp\/v2\/tags?post=10052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}